{"id":989061,"date":"2022-03-16T17:40:29","date_gmt":"2022-03-16T20:40:29","guid":{"rendered":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?p=989061"},"modified":"2022-03-18T08:43:21","modified_gmt":"2022-03-18T11:43:21","slug":"concurso-tcu-sugestao-de-recurso-afo-e-contabilidade-aplicada","status":"publish","type":"post","link":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-tcu-sugestao-de-recurso-afo-e-contabilidade-aplicada\/","title":{"rendered":"Concurso TCU: sugest\u00e3o de recurso para AFO e Contabilidade Aplicada"},"content":{"rendered":"\n<p><strong>Ol\u00e1, meus queridos alunos! Como est\u00e3o todos? Espero que firmes, fortes e bem de sa\u00fade!! :)<\/strong><\/p>\n\n\n\n<p><strong>Aqui \u00e9 a professora Gabriela Zavadinack e trarei para voc\u00eas sugest\u00e3o de dois recursos na prova de Administra\u00e7\u00e3o Financeira Or\u00e7ament\u00e1ria e uma na prova de Contabilidade Aplicada do Setor P\u00fablico, ambas do concurso TCU.<\/strong><\/p>\n\n\n\n<p><strong>Lembrando que a FGV \u00e9 bem r\u00edgida com rela\u00e7\u00e3o a recursos, gente. Ent\u00e3o caso voc\u00eas forem utilizar esses argumentos, \u00e9 necess\u00e1rio reescrever ou utilizar sin\u00f4nimos na argumenta\u00e7\u00e3o, visto que estou apenas sugerindo linhas argumentativas aqui, ok?<\/strong><\/p>\n\n\n\n<p><strong>N\u00c3O FA\u00c7AM COPIA E COLA<\/strong>!&nbsp;<\/p>\n\n\n\n<p><strong>Sem mais delongas, vamos l\u00e1.<\/strong><\/p>\n\n\n\n<p><strong>&nbsp;Instagram: @gabiprofessora&nbsp;<\/strong><\/p>\n\n\n\n<p><strong>AN\u00c1LISE DA PROVA TIPO 3<\/strong><\/p>\n\n\n\n<p><strong>Quest\u00e3o 91 &#8211; AFO<\/strong><\/p>\n\n\n\n<p>Apesar dos esfor\u00e7os que t\u00eam aperfei\u00e7oado o processo de planejamento or\u00e7ament\u00e1rio na administra\u00e7\u00e3o p\u00fablica brasileira, h\u00e1 previs\u00e3o da realiza\u00e7\u00e3o de altera\u00e7\u00f5es or\u00e7ament\u00e1rias ao longo do exerc\u00edcio financeiro. Tais altera\u00e7\u00f5es s\u00e3o limitadas, entre outros fatores, por imposi\u00e7\u00f5es legais e restri\u00e7\u00f5es de recursos. Um desafio para o controle externo analisar o montante e o impacto da abertura de cr\u00e9ditos adicionais no or\u00e7amento \u00e9 a:&nbsp;<\/p>\n\n\n\n<p>(A) falta de controle da edi\u00e7\u00e3o de medidas provis\u00f3rias com abertura de cr\u00e9ditos extraordin\u00e1rios;&nbsp;<\/p>\n\n\n\n<p>(B) impossibilidade de alterar um atributo de um cr\u00e9dito or\u00e7ament\u00e1rio, tal como modalidade de aplica\u00e7\u00e3o;&nbsp;<\/p>\n\n\n\n<p>(C) ocorr\u00eancia de reabertura de cr\u00e9ditos adicionais do exerc\u00edcio anterior no or\u00e7amento vigente;&nbsp;<\/p>\n\n\n\n<p><strong>(D) possibilidade de altera\u00e7\u00f5es or\u00e7ament\u00e1rias n\u00e3o inclu\u00eddas no limite de cr\u00e9ditos suplementares;&nbsp;<\/strong><\/p>\n\n\n\n<p>(E) recorr\u00eancia de situa\u00e7\u00f5es emergenciais que flexibilizam as regras de altera\u00e7\u00f5es or\u00e7ament\u00e1rias.<\/p>\n\n\n\n<p><strong>An\u00e1lise<\/strong>:<\/p>\n\n\n\n<p>O gabarito dado pela banca foi a letra D.&nbsp;<\/p>\n\n\n\n<p>Contudo, sugere-se a <strong>ANULA\u00c7\u00c3O<\/strong> da quest\u00e3o, visto que n\u00e3o h\u00e1 gabarito correto.&nbsp;<\/p>\n\n\n\n<p>Isso porque a possibilidade de altera\u00e7\u00f5es or\u00e7ament\u00e1rias n\u00e3o inclu\u00eddas no limite de cr\u00e9ditos suplementares ocorrer\u00e1 por meio da abertura de novos suplementares ou de cr\u00e9ditos especiais. Em ambos os casos ser\u00e1 necess\u00e1ria a indica\u00e7\u00e3o da fonte de recursos que financiar\u00e1 referidos cr\u00e9ditos, bem como a obrigatoriedade de serem precedidos de exposi\u00e7\u00e3o justificativa da necessidade de abertura (art. 43 da Lei \u00ba 4.320\/64). Por sua vez, ambos dever\u00e3o ser autorizados pelo Poder Legislativo (art. 42 da Lei n\u00ba 4.320\/64), o que deixa muito claro que os requisitos de abertura, nesses casos, <strong>facilitam<\/strong> o controle externo, n\u00e3o sendo um \u201cdesafio para o controle\u201d, como considerou a quest\u00e3o.<\/p>\n\n\n\n<p>Ainda, a t\u00edtulo de refor\u00e7o, o pr\u00f3prio Manual T\u00e9cnico Or\u00e7ament\u00e1rio (2021 \u2013 p\u00e1gs. 135 e 136) disp\u00f5e que:&nbsp;<\/p>\n\n\n\n<p>\u201c<em>Os cr\u00e9ditos suplementares podem ser divididos em duas modalidades:&nbsp;<\/em><\/p>\n\n\n\n<p><strong><em>Cr\u00e9ditos Suplementares autorizados na Lei Or\u00e7ament\u00e1ria<\/em><\/strong><em>: para refor\u00e7o de dota\u00e7\u00e3o insuficientemente dotada na LOA, nas condi\u00e7\u00f5es e limites estabelecidos na pr\u00f3pria LOA; e<\/em><\/p>\n\n\n\n<p><strong><em>Cr\u00e9ditos Suplementares dependentes de autoriza\u00e7\u00e3o legislativa<\/em><\/strong><em>: para refor\u00e7o de dota\u00e7\u00e3o insuficientemente dotada na LOA, acima dos limites autorizados na LOA, ou n\u00e3o autorizada no texto da referida lei.<\/em><\/p>\n\n\n\n<p><em>(&#8230;)<\/em><\/p>\n\n\n\n<p><em>8.4.2.1.2 Cr\u00e9ditos Especiais&nbsp;<\/em><\/p>\n\n\n\n<p><em>S\u00e3o destinados \u00e0 viabiliza\u00e7\u00e3o e atendimento de programas e despesas or\u00e7ament\u00e1rias para as quais n\u00e3o haja dota\u00e7\u00e3o or\u00e7ament\u00e1ria espec\u00edfica na Lei Or\u00e7ament\u00e1ria Anual. <\/em><em>Devem ter aprova\u00e7\u00e3o legislativa pr\u00e9via por meio de lei espec\u00edfica<\/em><em>. A abertura do cr\u00e9dito se dar\u00e1, no caso da Uni\u00e3o, com a publica\u00e7\u00e3o da <\/em><em>lei aprovada e sancionada<\/em><em>. Como \u00e9 <\/em><strong><em>necess\u00e1ria a exist\u00eancia de recursos dispon\u00edveis para a realiza\u00e7\u00e3o da despesa, a indica\u00e7\u00e3o de fontes de recursos, nos termos da Lei n\u00ba 4.320, de 1964, \u00e9 obrigat\u00f3ria, devendo constar das proposi\u00e7\u00f5es e atos de abertura, sendo precedida de exposi\u00e7\u00e3o justificada.<\/em><\/strong><em> A vig\u00eancia dos cr\u00e9ditos se esgota com o exerc\u00edcio financeiro em que foram abertos. Contudo, \u00e9 permitida a reabertura dos saldos para o exerc\u00edcio seguinte, desde que autorizados em um dos \u00faltimos quatro meses do exerc\u00edcio financeiro, caso em que ser\u00e3o incorporados ao or\u00e7amento do exerc\u00edcio financeiro subsequente<\/em>\u201d.&nbsp;<\/p>\n\n\n\n<p>Fica claro, portanto, que no \u00e2mbito das altera\u00e7\u00f5es or\u00e7ament\u00e1rias que ultrapassam o limite aprovado na LOA, n\u00e3o h\u00e1 qualquer desafio ao controle, visto que os cr\u00e9ditos suplementares dependentes de autoriza\u00e7\u00e3o legislativa e os cr\u00e9ditos especiais s\u00e3o, por \u00f3bvio, <strong>aprovados em LEI, com a respectivas indica\u00e7\u00e3o da fonte de recursos e da exposi\u00e7\u00e3o justificativa<\/strong>.&nbsp;<\/p>\n\n\n\n<p>N\u00e3o fosse o bastante, com rela\u00e7\u00e3o aos cr\u00e9ditos suplementares, estes s\u00e3o INCORPORADOS \u00c0 DOTA\u00c7\u00c3O que visam refor\u00e7ar, promovendo altera\u00e7\u00e3o quantitativa na Lei Or\u00e7ament\u00e1ria Anual, o que efetivamente facilita o controle externo.<\/p>\n\n\n\n<p><strong>Por sua vez, a \u00fanica modalidade de cr\u00e9ditos adicionais que configuraria um \u201cdesafio\u201d ao controle externo seria a abertura de cr\u00e9ditos EXTRAORDIN\u00c1RIOS<\/strong>, visto que s\u00e3o abertos por ato do Poder Executivo (medida provis\u00f3ria em \u00e2mbito federal \u2013 art. 167, \u00a7 3\u00ba, da CF\/88 \u2013 e decreto em \u00e2mbitos estadual\/municipal \u2013 art. 44 da Lei n\u00ba 4.320\/64), <strong>apenas havendo controle do Poder Legislativo posteriormente \u00e0 abertura. Somado a isso, s\u00e3o abertos sem a necessidade de indica\u00e7\u00e3o de fonte e sem a necessidade de exposi\u00e7\u00e3o justificativa<\/strong>. Esse seria um contexto em que haveria um desafio ao controle externo, visto que o cr\u00e9dito extraordin\u00e1rio (destinado a atender despesa urgente e imprevista), \u00e9 simplesmente aberto pelo Executivo e o controle fica postergado.<\/p>\n\n\n\n<p>Contudo, as letras \u201cA\u201d e \u201cE\u201d, que dizem respeito a cr\u00e9ditos adicionais extraordin\u00e1rios, tamb\u00e9m est\u00e3o erradas.&nbsp;<\/p>\n\n\n\n<p>Com rela\u00e7\u00e3o \u00e0 alternativa \u201cA\u201d, n\u00e3o h\u00e1 \u201cfalta de controle\u201d da edi\u00e7\u00e3o de medidas provis\u00f3rias. Em verdade, o art. 62 da Constitui\u00e7\u00e3o Federal de 1988 deixa claro que <em>\u201cEm caso de relev\u00e2ncia e urg\u00eancia, o Presidente da Rep\u00fablica poder\u00e1 adotar medidas provis\u00f3rias, com for\u00e7a de lei, <\/em><em>devendo submet\u00ea-las de imediato ao Congresso Nacional<\/em>\u201d. Al\u00e9m disso, o par\u00e1grafo 3\u00ba do mesmo artigo disp\u00f5e que \u201c<em>As medidas provis\u00f3rias, ressalvado o disposto nos \u00a7\u00a7 11 e 12 perder\u00e3o efic\u00e1cia, desde a edi\u00e7\u00e3o, <\/em><em>se n\u00e3o forem convertidas em lei no prazo de sessenta dias, prorrog\u00e1vel, nos termos do \u00a7 7\u00ba, uma vez por igual per\u00edodo, devendo o Congresso Nacional disciplinar, por decreto legislativo, as rela\u00e7\u00f5es jur\u00eddicas delas decorrentes<\/em>\u201d, bem como o par\u00e1grafo 5\u00ba n\u00e3o deixa d\u00favidas acerca do controle: \u201c<strong><em>A delibera\u00e7\u00e3o de cada uma das Casas do Congresso Nacional sobre o m\u00e9rito das medidas provis\u00f3rias <\/em><\/strong><strong><em>depender\u00e1 de ju\u00edzo pr\u00e9vio sobre o atendimento de seus pressupostos constitucionais<\/em><\/strong>\u201d. &nbsp; &nbsp;<\/p>\n\n\n\n<p>Assim, n\u00e3o obstante o controle n\u00e3o seja perfeito nesse caso, fato \u00e9 que n\u00e3o se pode falar em \u201cfalta de controle\u201d com rela\u00e7\u00e3o \u00e0 edi\u00e7\u00e3o de medidas provis\u00f3rias.<\/p>\n\n\n\n<p>Por sua vez, a letra \u201cE\u201d tamb\u00e9m cont\u00e9m problemas, n\u00e3o podendo servir como gabarito da quest\u00e3o. Isso porque os cr\u00e9ditos extraordin\u00e1rios s\u00e3o abertos para atender a despesas \u201c<strong><em>imprevis\u00edveis e urgentes<\/em><\/strong><em>, como as decorrentes de guerra, como\u00e7\u00e3o interna ou calamidade p\u00fablica<\/em>\u201d, nos moldes do artigo 167, \u00a7 3\u00ba, da CF\/88. Da mesma forma, a Lei n\u00ba 4.320\/64 preceitua, em seu artigo 41, III, que os cr\u00e9ditos extraordin\u00e1rios s\u00e3o os \u201c<em>destinados a despesas <\/em><strong><em>urgentes e imprevistas<\/em><\/strong><em>, em caso de guerra, como\u00e7\u00e3o intestina ou calamidade p\u00fablica<\/em>\u201d.<\/p>\n\n\n\n<p>Nesse cen\u00e1rio, a alternativa \u201cE\u201d, ao tratar sobre \u201c<em>recorr\u00eancia de situa\u00e7\u00f5es emergenciais que flexibilizam as regras de altera\u00e7\u00f5es or\u00e7ament\u00e1rias<\/em>\u201d n\u00e3o traz o termo \u201cimprevistas\u201d (o que \u00e9 um requisito cumulativo para abertura de cr\u00e9ditos extraordin\u00e1rios), bem como utiliza o termo \u201crecorr\u00eancia\u201d, como se a abertura de cr\u00e9ditos extraordin\u00e1rios fosse a regra. A despeito de o pa\u00eds ter passado por um momento de calamidade p\u00fablica nos \u00faltimos dois anos, isso n\u00e3o \u00e9 a regra. Somado a isso, conforme j\u00e1 explanado, n\u00e3o basta que a situa\u00e7\u00e3o seja urgente, devendo, tamb\u00e9m, estar completamente fora do \u00e2mbito de previsibilidade. Dessa forma, situa\u00e7\u00f5es urgentes podem ocorrer, sem d\u00favidas, mas para abertura de cr\u00e9ditos extraordin\u00e1rios, \u00e9 obrigat\u00f3rio que tal situa\u00e7\u00e3o tamb\u00e9m n\u00e3o tenho sido prevista de forma alguma. Portanto, a recorr\u00eancia de situa\u00e7\u00f5es emergenciais, por si s\u00f3, n\u00e3o \u00e9 suficiente para se abrir um cr\u00e9dito extraordin\u00e1rio (flexibiliza\u00e7\u00e3o das regras de altera\u00e7\u00f5es or\u00e7ament\u00e1rias), devendo o contexto ser imprevis\u00edvel, como em decorr\u00eancia de guerra, como\u00e7\u00e3o interna ou calamidade p\u00fablica.<\/p>\n\n\n\n<p>N\u00e3o h\u00e1, portanto, gabarito correto. Sugere-se a ANULA\u00c7\u00c3O da quest\u00e3o.<\/p>\n\n\n\n<p><strong>Quest\u00e3o 96&nbsp; &#8211; AFO<\/strong><\/p>\n\n\n\n<p>A Superintend\u00eancia do Patrim\u00f4nio da Uni\u00e3o no Estado Alfa teve que indicar a classifica\u00e7\u00e3o de suas receitas referentes a foro e taxa de ocupa\u00e7\u00e3o quanto a terrenos de marinha localizados no referido Estado, bem como a classifica\u00e7\u00e3o da despesa para aquisi\u00e7\u00e3o de im\u00f3vel tido como necess\u00e1rio para a execu\u00e7\u00e3o de obra p\u00fablica. Levando-se em considera\u00e7\u00e3o a classifica\u00e7\u00e3o por natureza de cada uma dessas receitas e despesa p\u00fablicas descritas no enunciado, \u00e0 luz da Lei n\u00ba 4.320\/1964, \u00e9 correto afirmar que tais receitas:&nbsp;<\/p>\n\n\n\n<p>(A) de foro e de taxa de ocupa\u00e7\u00e3o s\u00e3o classificadas como receitas tribut\u00e1rias, e a despesa com a aquisi\u00e7\u00e3o imobili\u00e1ria necess\u00e1ria \u00e0 execu\u00e7\u00e3o de obra p\u00fablica, como invers\u00e3o financeira;&nbsp;<\/p>\n\n\n\n<p>(B) de foro s\u00e3o classificadas como receitas patrimoniais, as de taxa de ocupa\u00e7\u00e3o como receitas tribut\u00e1rias, e a despesa com a aquisi\u00e7\u00e3o imobili\u00e1ria necess\u00e1ria \u00e0 execu\u00e7\u00e3o de obra p\u00fablica, como invers\u00e3o financeira;&nbsp;<\/p>\n\n\n\n<p>(C) de foro s\u00e3o classificadas como receitas patrimoniais, as de taxa de ocupa\u00e7\u00e3o como receitas tribut\u00e1rias, e a despesa com a aquisi\u00e7\u00e3o imobili\u00e1ria necess\u00e1ria \u00e0 execu\u00e7\u00e3o de obra p\u00fablica, como investimento;&nbsp;<\/p>\n\n\n\n<p>(D) de foro e de taxa de ocupa\u00e7\u00e3o s\u00e3o classificadas como receitas patrimoniais, e a despesa com a aquisi\u00e7\u00e3o imobili\u00e1ria necess\u00e1ria \u00e0 execu\u00e7\u00e3o de obra p\u00fablica, como invers\u00e3o financeira;&nbsp;<\/p>\n\n\n\n<p><strong>(E) de foro e de taxa de ocupa\u00e7\u00e3o s\u00e3o classificadas como receitas patrimoniais, e a despesa com a aquisi\u00e7\u00e3o imobili\u00e1ria necess\u00e1ria \u00e0 execu\u00e7\u00e3o de obra p\u00fablica, como investimento.<\/strong><\/p>\n\n\n\n<p><strong>An\u00e1lise<\/strong>:<\/p>\n\n\n\n<p>O gabarito dado pela banca foi a letra E.&nbsp;<\/p>\n\n\n\n<p>Contudo, sugere-se a ANULA\u00c7\u00c3O da quest\u00e3o, visto que a classifica\u00e7\u00e3o apresentada no gabarito n\u00e3o est\u00e1 prevista na Lei n\u00ba 4.320\/64.<\/p>\n\n\n\n<p>O comando da quest\u00e3o \u00e9 expresso ao requerer que a an\u00e1lise das classifica\u00e7\u00f5es se d\u00ea de acordo com a Lei n\u00ba 4.320\/64: \u201c<em>Levando-se em considera\u00e7\u00e3o a classifica\u00e7\u00e3o por natureza de cada uma dessas receitas e despesa p\u00fablicas descritas no enunciado, <\/em><strong><em>\u00e0 luz da Lei n\u00ba 4.320\/1964<\/em><\/strong><em>, \u00e9 correto afirmar que tais receitas<\/em>:\u201d.<\/p>\n\n\n\n<p><strong>Ocorre que a Lei n\u00ba 4.320\/64 n\u00e3o classifica as esp\u00e9cies \u201cforo\u201d e \u201ctaxa de ocupa\u00e7\u00e3o\u201d em nenhuma origem<\/strong>. Importante registrar que o \u00fanico momento em que a Lei n\u00ba 4.320\/64 traz os termos \u201cforo\u201d e \u201ctaxas de ocupa\u00e7\u00e3o\u201d ocorre em seu artigo 39, \u00a7 2\u00ba, que assim preceitua:<\/p>\n\n\n\n<p><em>\u201c\u00a7 2\u00ba &#8211; D\u00edvida Ativa Tribut\u00e1ria \u00e9 o cr\u00e9dito da Fazenda P\u00fablica dessa natureza, proveniente de obriga\u00e7\u00e3o legal relativa a tributos e respectivos adicionais e multas, <\/em><strong><em>e D\u00edvida Ativa n\u00e3o Tribut\u00e1ria s\u00e3o os demais cr\u00e9ditos da Fazenda P\u00fablica, tais como<\/em><\/strong><em> os provenientes de empr\u00e9stimos compuls\u00f3rios, contribui\u00e7\u00f5es estabelecidas em lei, multa de qualquer origem ou natureza, exceto as tribut\u00e1rias, <\/em><strong><em>foros<\/em><\/strong><em>, laud\u00eamios, alugueis ou <\/em><strong><em>taxas de ocupa\u00e7\u00e3o<\/em><\/strong><em>, custas processuais, pre\u00e7os de servi\u00e7os prestados por estabelecimentos p\u00fablicos, indeniza\u00e7\u00f5es, reposi\u00e7\u00f5es, restitui\u00e7\u00f5es, alcances dos respons\u00e1veis definitivamente julgados, bem assim os cr\u00e9ditos decorrentes de obriga\u00e7\u00f5es em moeda estrangeira, de subroga\u00e7\u00e3o de hipoteca, fian\u00e7a, aval ou outra garantia, de contratos em geral ou de outras obriga\u00e7\u00f5es legais\u201d.&nbsp; &nbsp; &nbsp; &nbsp; &nbsp;<\/em><\/p>\n\n\n\n<p>Tal classifica\u00e7\u00e3o diz respeito somente \u00e0 D\u00edvida Ativa, podendo-se extrair da lei, unicamente, que foros e taxas de ocupa\u00e7\u00e3o ser\u00e3o inscritos como \u201cd\u00edvida ativa n\u00e3o tribut\u00e1ria\u201d, n\u00e3o havendo qualquer men\u00e7\u00e3o \u00e0 qual origem essas esp\u00e9cies de receita pertencem.<\/p>\n\n\n\n<p>Por sua vez, da an\u00e1lise dos anexos que integram a Lei n\u00ba 4.320\/64, tamb\u00e9m n\u00e3o se extrai a referida classifica\u00e7\u00e3o. Em verdade, a p\u00e1gina 4 do documento previsto no <em>link<\/em> \u201cDownload para Anexos\u201d (http:\/\/www.planalto.gov.br\/ccivil_03\/leis\/1950-1969\/anexo\/ANL4320-64.pdf) traz apenas quatro esp\u00e9cies de receita patrimonial: receitas imobili\u00e1rias, receitas de valores mobili\u00e1rios, participa\u00e7\u00f5es e dividendos, outras receitas patrimoniais.<\/p>\n\n\n\n<p><strong>A classifica\u00e7\u00e3o das esp\u00e9cies foros e \u201ctarifas\u201d de ocupa\u00e7\u00e3o encontra-se apenas prevista em Portarias da Secretaria de Or\u00e7amento Federal (SOF)<\/strong>. Verifica-se que o primeiro momento em que o c\u00f3digo \u201c1.3.1.0.01.2.0 &#8211; Foros, Laud\u00eamios e Tarifas de Ocupa\u00e7\u00e3o\u201d foi inclu\u00eddo na origem Patrimonial ocorreu com a Portaria n\u00ba 10, de 1\u00ba de fevereiro de 2016 (publica\u00e7\u00e3o no DOU em 03\/12\/2016), a qual assim disp\u00f4s:<\/p>\n\n\n\n<p><em>\u201cConsiderando que o aprimoramento do processo or\u00e7ament\u00e1rio imp\u00f5e a constante revis\u00e3o das classifica\u00e7\u00f5es or\u00e7ament\u00e1rias das receitas da Uni\u00e3o, resolve:&nbsp;<\/em><\/p>\n\n\n\n<p><em>Art. 1\u00ba Incluir, no Anexo da Portaria SOF no 45, de 26 de agosto de 2015, as seguintes naturezas de receita:<\/em><\/p>\n\n\n\n<p><em>1.3.1.0.01.2.0 &#8211; <\/em><strong><em>Foros<\/em><\/strong><em>, Laud\u00eamios e <\/em><strong><em>Tarifas de Ocupa\u00e7\u00e3o<\/em><\/strong><em>\u201d.<\/em><\/p>\n\n\n\n<p>Portanto, uma vez que a classifica\u00e7\u00e3o relativa a foros e taxas de ocupa\u00e7\u00e3o n\u00e3o est\u00e1 prevista na Lei n\u00ba 4.320\/64, nem nos anexos que comp\u00f5em a referida lei, sugere-se a ANULA\u00c7\u00c3O da quest\u00e3o, visto que o conte\u00fado abordado nas alternativas extrapola o comando da quest\u00e3o <em>(\u201c\u00e0 luz da Lei n\u00ba 4.320\/64\u201d<\/em>).<\/p>\n\n\n\n<p><strong>Quest\u00e3o 85 &#8211; CASP<\/strong><\/p>\n\n\n\n<p>Um dos demonstrativos constantes do Relat\u00f3rio Resumido da Execu\u00e7\u00e3o Or\u00e7ament\u00e1ria refere-se \u00e0 apura\u00e7\u00e3o da Receita Corrente L\u00edquida (RCL), que \u00e9 um par\u00e2metro usado como refer\u00eancia para defini\u00e7\u00e3o da reserva de conting\u00eancia e para acompanhamento dos limites fiscais, tais como despesa total com pessoal e endividamento. Ao analisar o Demonstrativo da Receita Corrente L\u00edquida de um Estado da federa\u00e7\u00e3o, por exemplo, um servidor da \u00e1rea de controle externo deve considerar que:&nbsp;<\/p>\n\n\n\n<p>(A) as receitas de transfer\u00eancias correntes s\u00e3o computadas de forma dedutiva;&nbsp;<\/p>\n\n\n\n<p>(B) as receitas provenientes da compensa\u00e7\u00e3o financeira entre regimes previdenci\u00e1rios s\u00e3o computadas de forma aditiva;&nbsp;<\/p>\n\n\n\n<p>(C) as transfer\u00eancias da Uni\u00e3o relativas a emendas impositivas de bancada afetam a RCL para fins dos limites de endividamento;&nbsp;<\/p>\n\n\n\n<p><strong>(D) as transfer\u00eancias da Uni\u00e3o relativas a emendas impositivas individuais afetam a RCL para fins do limite da despesa com pessoal;&nbsp;<\/strong><\/p>\n\n\n\n<p>(E) os rendimentos de aplica\u00e7\u00e3o financeira referentes aos recursos do regime pr\u00f3prio de previd\u00eancia social n\u00e3o afetam a RCL.<\/p>\n\n\n\n<p><strong>An\u00e1lise<\/strong>:<\/p>\n\n\n\n<p>O gabarito dado pela banca foi a letra D.&nbsp;<\/p>\n\n\n\n<p>Contudo, sugere-se a anula\u00e7\u00e3o da quest\u00e3o.<\/p>\n\n\n\n<p>Pessoal, sei que aqui algumas pessoas v\u00e3o discordar, mas a meu ver, temos alguns problemas nessa quest\u00e3o.<\/p>\n\n\n\n<p>Primeiramente, importante mencionar que a letra \u201cE\u201d traz uma l\u00f3gica que s\u00f3 passou a ser prevista no Manual de Demonstrativos Fiscais 12\u00aa edi\u00e7\u00e3o (2022) \u2013 posterior \u00e0 publica\u00e7\u00e3o do edital. A partir de 2022, os rendimentos de aplica\u00e7\u00e3o financeira referentes aos recursos do regime pr\u00f3prio de previd\u00eancia social passaram a ser deduzidos dos c\u00e1lculos da receita corrente l\u00edquida nas tr\u00eas esferas de governo. <strong>Ocorre que o edital de CONTABILIDADE APLICADA AO SETOR P\u00daBLICO n\u00e3o cobra o referido MDF, mas apenas o Manual de Contabilidade Aplicada ao Setor P\u00fablico (MCASP)<\/strong><strong>.<\/strong><\/p>\n\n\n\n<p>Dessa forma, entende-se que a cobran\u00e7a, em uma das alternativas, de um texto que est\u00e1 expressamente previsto apenas no MDF 12\u00aa edi\u00e7\u00e3o (2022), posterior e n\u00e3o previsto no edital, j\u00e1 invalidaria a quest\u00e3o.<\/p>\n\n\n\n<p>Por sua vez, para que houvesse a marca\u00e7\u00e3o da letra \u201cD\u201d como gabarito, seria imprescind\u00edvel que o candidato tivesse analisado o item \u201c<em>03.03.05.01 &#8211; Tabela 3 \u2013 Demonstrativo da Receita Corrente L\u00edquida<\/em>\u201d do Manual de Demonstrativos Fiscais 11\u00aa edi\u00e7\u00e3o (2021 \u2013 3\u00aa vers\u00e3o) (https:\/\/sisweb.tesouro.gov.br\/apex\/f?p=2501:9::::9:P9_ID_PUBLICACAO:33576 \u2013 p\u00e1g. 207), em que fica claro que as Transfer\u00eancias obrigat\u00f3rias da Uni\u00e3o relativas \u00e0s emendas individuais ser\u00e3o deduzidas do c\u00e1lculo da Receita Corrente L\u00edquida, afetando, portanto o referido c\u00e1lculo.<\/p>\n\n\n\n<p>Tal an\u00e1lise seria necess\u00e1ria porque tanto o MCASP (itens 6.1, 6.2 e 6.3 do edital) quanto a Lei de Responsabilidade Fiscal (item 5 do edital) <strong>n\u00e3o disp\u00f5em<\/strong> sobre o assunto da contabiliza\u00e7\u00e3o das referidas emendas no c\u00e1lculo da RCL.&nbsp;<\/p>\n\n\n\n<p>Somado a isso, a despeito de o art. 166, \u00a7 16, da Constitui\u00e7\u00e3o Federal de 1988 tamb\u00e9m n\u00e3o estar previsto no edital de Contabilidade aplicada ao Setor P\u00fablico, \u00e9 importante destacar que o referido dispositivo preceitua que <em>\u201cQuando a transfer\u00eancia obrigat\u00f3ria da Uni\u00e3o para a execu\u00e7\u00e3o da programa\u00e7\u00e3o prevista nos \u00a7\u00a7 11 e 12 deste artigo for destinada a Estados, ao Distrito Federal e a Munic\u00edpios, independer\u00e1 da adimpl\u00eancia do ente federativo destinat\u00e1rio e <\/em><strong><em>n\u00e3o integrar\u00e1 a base de c\u00e1lculo da receita corrente l\u00edquida para fins de aplica\u00e7\u00e3o dos limites de despesa de pessoal<\/em><\/strong><em> de que trata o caput do art. 169<\/em>\u201d.<\/p>\n\n\n\n<p>O termo \u201cn\u00e3o integrar\u00e1\u201d a base de c\u00e1lculo, previsto na CF\/88, n\u00e3o implica interpreta\u00e7\u00e3o no sentido de que haver\u00e1 dedu\u00e7\u00e3o, mas somente de que tais transfer\u00eancias n\u00e3o afetar\u00e3o o c\u00e1lculo da receita corrente l\u00edquida para fins de despesa com pessoal, visto que n\u00e3o integrar\u00e3o a base de c\u00e1lculo.<\/p>\n\n\n\n<p>Dessa forma, entende-se que o termo \u201cafetam\u201d poderia ser interpretado de duas maneiras: de acordo com o art. 166, \u00a7 16, da CF\/88, n\u00e3o previsto no edital<strong>,<\/strong> ao <strong>n\u00e3o integrar a base de c\u00e1lculo<\/strong> da receita corrente l\u00edquida, as transfer\u00eancias para emendas impositivas <strong>n\u00e3o afetariam a RCL<\/strong> para fins de despesa com pessoal. J\u00e1 da an\u00e1lise do Manual de Demonstrativos Fiscais 11\u00aa edi\u00e7\u00e3o (2021 \u2013 3\u00aa vers\u00e3o), tamb\u00e9m n\u00e3o previsto no edital, entender-se-ia que tais valores <strong>afetariam o c\u00e1lculo, visto que s\u00e3o deduzidos do c\u00e1lculo da RCL<\/strong>.<\/p>\n\n\n\n<p><strong>Portanto, muito embora as transfer\u00eancias obrigat\u00f3rias da Uni\u00e3o para a execu\u00e7\u00e3o das emendas individuais impositivas <\/strong><strong>serem efetivamente deduzidas<\/strong><strong> do c\u00e1lculo da receita corrente l\u00edquida, conforme se extrai da p\u00e1gina 207 do MDF 11\u00aa ed. (2021 \u2013 3\u00aa vers\u00e3o), <\/strong><strong>tal conclus\u00e3o apenas poderia ser alcan\u00e7ada por meio do estudo do Manual de Demonstrativos Fiscais, o qual n\u00e3o foi previsto no edital<\/strong>.&nbsp;<\/p>\n\n\n\n<p>Assim, sugere-se a ANULA\u00c7\u00c3O da quest\u00e3o, visto que o gabarito apontado como correto possui fundamento no Manual de Demonstrativos Fiscais 11\u00aa edi\u00e7\u00e3o (2021 \u2013 3\u00aa vers\u00e3o), <strong>n\u00e3o previsto no edital no edital de Contabilidade Aplicada ao Setor P\u00fablico, disciplina na qual a quest\u00e3o foi exigida.<\/strong><\/p>\n\n\n\n<p>Ent\u00e3o \u00e9 isso, pessoal!<\/p>\n\n\n\n<p>Para quem ainda tiver d\u00favidas, pode entrar em contato comigo por meio do Instagram: @gabiprofessora.&nbsp;<\/p>\n\n\n\n<p>At\u00e9!<\/p>\n\n\n\n\n","protected":false},"excerpt":{"rendered":"<p>Ol\u00e1, meus queridos alunos! Como est\u00e3o todos? Espero que firmes, fortes e bem de sa\u00fade!! :) Aqui \u00e9 a professora Gabriela Zavadinack e trarei para voc\u00eas sugest\u00e3o de dois recursos na prova de Administra\u00e7\u00e3o Financeira Or\u00e7ament\u00e1ria e uma na prova de Contabilidade Aplicada do Setor P\u00fablico, ambas do concurso TCU. Lembrando que a FGV \u00e9 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":984592,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"post_tipo":"article","footnotes":""},"categories":[214710],"tags":[],"tax_estado":[219963],"class_list":["post-989061","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tribunais-de-contas","tax_estado-concursos-federais"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.2 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Concurso TCU: sugest\u00e3o de recurso para AFO e Contabilidade Aplicada<\/title>\n<meta name=\"description\" content=\"sugest\u00e3o de dois recursos na prova de AFO e uma na prova de Contabilidade Aplicada do Setor P\u00fablico, ambas do concurso TCU.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-tcu-sugestao-de-recurso-afo-e-contabilidade-aplicada\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Concurso TCU: sugest\u00e3o de recurso para AFO e Contabilidade Aplicada\" \/>\n<meta property=\"og:description\" content=\"sugest\u00e3o de dois recursos na prova de AFO e uma na prova de Contabilidade Aplicada do Setor P\u00fablico, ambas do concurso TCU.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-tcu-sugestao-de-recurso-afo-e-contabilidade-aplicada\/\" \/>\n<meta property=\"og:site_name\" content=\"Estrat\u00e9gia Concursos\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/EstrategiaConcursos\" \/>\n<meta property=\"article:published_time\" content=\"2022-03-16T20:40:29+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-03-18T11:43:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/03\/10141713\/tcu-tribunaldecontas-fachada-frente-111-scaled-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1833\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Coordena\u00e7\u00e3o\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:site\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Coordena\u00e7\u00e3o\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"16 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-tcu-sugestao-de-recurso-afo-e-contabilidade-aplicada\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-tcu-sugestao-de-recurso-afo-e-contabilidade-aplicada\/\"},\"author\":{\"name\":\"Coordena\u00e7\u00e3o\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/b4a388c97673c5f483d72185668afa1f\"},\"headline\":\"Concurso TCU: sugest\u00e3o de recurso para AFO e Contabilidade Aplicada\",\"datePublished\":\"2022-03-16T20:40:29+00:00\",\"dateModified\":\"2022-03-18T11:43:21+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-tcu-sugestao-de-recurso-afo-e-contabilidade-aplicada\/\"},\"wordCount\":3220,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-tcu-sugestao-de-recurso-afo-e-contabilidade-aplicada\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/03\/10141713\/tcu-tribunaldecontas-fachada-frente-111-scaled-1.jpg\",\"articleSection\":[\"Tribunais de Contas (TCU, TCE, TCM)\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-tcu-sugestao-de-recurso-afo-e-contabilidade-aplicada\/#respond\"]}],\"copyrightYear\":\"2022\",\"copyrightHolder\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-tcu-sugestao-de-recurso-afo-e-contabilidade-aplicada\/\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-tcu-sugestao-de-recurso-afo-e-contabilidade-aplicada\/\",\"name\":\"Concurso TCU: sugest\u00e3o de recurso para AFO e Contabilidade Aplicada\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-tcu-sugestao-de-recurso-afo-e-contabilidade-aplicada\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-tcu-sugestao-de-recurso-afo-e-contabilidade-aplicada\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/03\/10141713\/tcu-tribunaldecontas-fachada-frente-111-scaled-1.jpg\",\"datePublished\":\"2022-03-16T20:40:29+00:00\",\"dateModified\":\"2022-03-18T11:43:21+00:00\",\"description\":\"sugest\u00e3o de dois recursos na prova de AFO e uma na prova de Contabilidade Aplicada do Setor P\u00fablico, ambas do concurso TCU.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-tcu-sugestao-de-recurso-afo-e-contabilidade-aplicada\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-tcu-sugestao-de-recurso-afo-e-contabilidade-aplicada\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-tcu-sugestao-de-recurso-afo-e-contabilidade-aplicada\/#primaryimage\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/03\/10141713\/tcu-tribunaldecontas-fachada-frente-111-scaled-1.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/03\/10141713\/tcu-tribunaldecontas-fachada-frente-111-scaled-1.jpg\",\"width\":2560,\"height\":1833},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-tcu-sugestao-de-recurso-afo-e-contabilidade-aplicada\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Concurso TCU: sugest\u00e3o de recurso para AFO e Contabilidade Aplicada\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"name\":\"Estrat\u00e9gia Concursos\",\"description\":\"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.\",\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\",\"name\":\"Estrat\u00e9gia Concursos\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"width\":230,\"height\":60,\"caption\":\"Estrat\u00e9gia Concursos\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/EstratConcursos\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/b4a388c97673c5f483d72185668afa1f\",\"name\":\"Coordena\u00e7\u00e3o\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/b720319e4c9a967eb58678d110f4fe35452fc5d5f97b202bac7b8acceb18c6ad?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/b720319e4c9a967eb58678d110f4fe35452fc5d5f97b202bac7b8acceb18c6ad?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/b720319e4c9a967eb58678d110f4fe35452fc5d5f97b202bac7b8acceb18c6ad?s=96&d=mm&r=g\",\"caption\":\"Coordena\u00e7\u00e3o\"},\"sameAs\":[\"https:\/\/www.facebook.com\/EstrategiaConcursos\",\"https:\/\/x.com\/EstratConcursos\"],\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/estrategia2013\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Concurso TCU: sugest\u00e3o de recurso para AFO e Contabilidade Aplicada","description":"sugest\u00e3o de dois recursos na prova de AFO e uma na prova de Contabilidade Aplicada do Setor P\u00fablico, ambas do concurso TCU.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-tcu-sugestao-de-recurso-afo-e-contabilidade-aplicada\/","og_locale":"pt_BR","og_type":"article","og_title":"Concurso TCU: sugest\u00e3o de recurso para AFO e Contabilidade Aplicada","og_description":"sugest\u00e3o de dois recursos na prova de AFO e uma na prova de Contabilidade Aplicada do Setor P\u00fablico, ambas do concurso TCU.","og_url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-tcu-sugestao-de-recurso-afo-e-contabilidade-aplicada\/","og_site_name":"Estrat\u00e9gia Concursos","article_author":"https:\/\/www.facebook.com\/EstrategiaConcursos","article_published_time":"2022-03-16T20:40:29+00:00","article_modified_time":"2022-03-18T11:43:21+00:00","og_image":[{"width":2560,"height":1833,"url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/03\/10141713\/tcu-tribunaldecontas-fachada-frente-111-scaled-1.jpg","type":"image\/jpeg"}],"author":"Coordena\u00e7\u00e3o","twitter_card":"summary_large_image","twitter_creator":"@EstratConcursos","twitter_site":"@EstratConcursos","twitter_misc":{"Escrito por":"Coordena\u00e7\u00e3o","Est. tempo de leitura":"16 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-tcu-sugestao-de-recurso-afo-e-contabilidade-aplicada\/#article","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-tcu-sugestao-de-recurso-afo-e-contabilidade-aplicada\/"},"author":{"name":"Coordena\u00e7\u00e3o","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/b4a388c97673c5f483d72185668afa1f"},"headline":"Concurso TCU: sugest\u00e3o de recurso para AFO e Contabilidade Aplicada","datePublished":"2022-03-16T20:40:29+00:00","dateModified":"2022-03-18T11:43:21+00:00","mainEntityOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-tcu-sugestao-de-recurso-afo-e-contabilidade-aplicada\/"},"wordCount":3220,"commentCount":0,"publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-tcu-sugestao-de-recurso-afo-e-contabilidade-aplicada\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/03\/10141713\/tcu-tribunaldecontas-fachada-frente-111-scaled-1.jpg","articleSection":["Tribunais de Contas (TCU, TCE, TCM)"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-tcu-sugestao-de-recurso-afo-e-contabilidade-aplicada\/#respond"]}],"copyrightYear":"2022","copyrightHolder":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-tcu-sugestao-de-recurso-afo-e-contabilidade-aplicada\/","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-tcu-sugestao-de-recurso-afo-e-contabilidade-aplicada\/","name":"Concurso TCU: sugest\u00e3o de recurso para AFO e Contabilidade Aplicada","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-tcu-sugestao-de-recurso-afo-e-contabilidade-aplicada\/#primaryimage"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-tcu-sugestao-de-recurso-afo-e-contabilidade-aplicada\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/03\/10141713\/tcu-tribunaldecontas-fachada-frente-111-scaled-1.jpg","datePublished":"2022-03-16T20:40:29+00:00","dateModified":"2022-03-18T11:43:21+00:00","description":"sugest\u00e3o de dois recursos na prova de AFO e uma na prova de Contabilidade Aplicada do Setor P\u00fablico, ambas do concurso TCU.","breadcrumb":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-tcu-sugestao-de-recurso-afo-e-contabilidade-aplicada\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-tcu-sugestao-de-recurso-afo-e-contabilidade-aplicada\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-tcu-sugestao-de-recurso-afo-e-contabilidade-aplicada\/#primaryimage","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/03\/10141713\/tcu-tribunaldecontas-fachada-frente-111-scaled-1.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/03\/10141713\/tcu-tribunaldecontas-fachada-frente-111-scaled-1.jpg","width":2560,"height":1833},{"@type":"BreadcrumbList","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-tcu-sugestao-de-recurso-afo-e-contabilidade-aplicada\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.estrategiaconcursos.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Concurso TCU: sugest\u00e3o de recurso para AFO e Contabilidade Aplicada"}]},{"@type":"WebSite","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","name":"Estrat\u00e9gia Concursos","description":"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.","publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization","name":"Estrat\u00e9gia Concursos","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","width":230,"height":60,"caption":"Estrat\u00e9gia Concursos"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/EstratConcursos"]},{"@type":"Person","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/b4a388c97673c5f483d72185668afa1f","name":"Coordena\u00e7\u00e3o","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/b720319e4c9a967eb58678d110f4fe35452fc5d5f97b202bac7b8acceb18c6ad?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b720319e4c9a967eb58678d110f4fe35452fc5d5f97b202bac7b8acceb18c6ad?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b720319e4c9a967eb58678d110f4fe35452fc5d5f97b202bac7b8acceb18c6ad?s=96&d=mm&r=g","caption":"Coordena\u00e7\u00e3o"},"sameAs":["https:\/\/www.facebook.com\/EstrategiaConcursos","https:\/\/x.com\/EstratConcursos"],"url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/estrategia2013\/"}]}},"_links":{"self":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/989061","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/comments?post=989061"}],"version-history":[{"count":2,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/989061\/revisions"}],"predecessor-version":[{"id":989090,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/989061\/revisions\/989090"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media\/984592"}],"wp:attachment":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media?parent=989061"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/categories?post=989061"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tags?post=989061"},{"taxonomy":"tax_estado","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tax_estado?post=989061"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}