{"id":981522,"date":"2022-03-16T08:07:00","date_gmt":"2022-03-16T11:07:00","guid":{"rendered":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?p=981522"},"modified":"2023-08-31T11:00:07","modified_gmt":"2023-08-31T14:00:07","slug":"abuso-de-autoridade-para-sefaz-pa","status":"publish","type":"post","link":"https:\/\/www.estrategiaconcursos.com.br\/blog\/abuso-de-autoridade-para-sefaz-pa\/","title":{"rendered":"Resumo da Lei do abuso de autoridade para SEFAZ-PA \u2013 Lei 13.869\/2019"},"content":{"rendered":"\n<p>Ol\u00e1, pessoal. Tudo certo? No artigo de hoje veremos o Resumo da Lei do abuso de autoridade para SEFAZ-PA \u2013 Lei 13.869\/2019.<\/p>\n\n\n\n<p>Como estamos em reta final, vamos tentar separar aquilo que de fato tem mais chance de aparecer em sua prova, combinado?<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"230\" height=\"204\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/03\/05141039\/image-57.png\" alt=\"Resumo da Lei do abuso de autoridade para SEFAZ-PA \u2013 Lei 13.869\/2019\" class=\"wp-image-981525\"\/><figcaption class=\"wp-element-caption\">Resumo da Lei do abuso de autoridade para SEFAZ-PA \u2013 Lei 13.869\/2019<\/figcaption><\/figure>\n\n\n\n<p>Sem mais delongas, vamos l\u00e1.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-disposicoes-gerais\">Disposi\u00e7\u00f5es gerais<\/h2>\n\n\n\n<p>Iniciando o Resumo da Lei do abuso de autoridade para SEFAZ-PA \u2013 Lei 13.869\/2019, vejamos as disposi\u00e7\u00f5es gerais.<\/p>\n\n\n\n<p><strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-cyan-blue-color\">Crimes de abuso de autoridade:<\/mark> cometidos por agente p\u00fablico<\/strong>, <strong>servidor ou n\u00e3o<\/strong>, que, no exerc\u00edcio de suas fun\u00e7\u00f5es ou a pretexto de exerc\u00ea-las, <strong>abuse do poder que lhe tenha sido atribu\u00eddo<\/strong>.<\/p>\n\n\n\n<p><strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-green-cyan-color\">Requisitos para configurar crime:<\/mark><\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>prejudicar outrem<\/strong>; ou<\/li>\n\n\n\n<li><strong>beneficiar a si mesmo <\/strong>ou a <strong>terceiro; <\/strong>ou<\/li>\n\n\n\n<li>por <strong>mero capricho ou satisfa\u00e7\u00e3o pessoal<\/strong><\/li>\n<\/ul>\n\n\n\n<p>Atente-se que na mera <strong>diverg\u00eancia<\/strong> na interpreta\u00e7\u00e3o de lei ou na avalia\u00e7\u00e3o de fatos e provas <strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-red-color\">n\u00e3o <\/mark>configura abuso de autoridade<\/strong> (Art. 1, \u00a72\u00ba).<\/p>\n\n\n\n<p>Ainda, o sujeito ativo dos crimes de abuso de autoridade \u00e9 o agente p\u00fablico. Conhe\u00e7amos a defini\u00e7\u00e3o.<\/p>\n\n\n\n<p><strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-green-cyan-color\">Agente p\u00fablico<\/mark> <\/strong>(Art. 2\u00ba, \u00a7\u00fa): <strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-red-color\">todo <\/mark>aquele que exerce<\/strong>, ainda que <strong>transitoriamente<\/strong> ou sem remunera\u00e7\u00e3o, por elei\u00e7\u00e3o, nomea\u00e7\u00e3o, designa\u00e7\u00e3o, contrata\u00e7\u00e3o ou qualquer outra forma de investidura ou v\u00ednculo, <strong>mandato, cargo, emprego ou fun\u00e7\u00e3o<\/strong> em \u00f3rg\u00e3o ou entidade (Art. 2\u00ba, \u00a7 \u00fanico)<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-da-condenacao-e-das-penas-restritivas\">Da Condena\u00e7\u00e3o e das Penas Restritivas<\/h2>\n\n\n\n<p>Dando continuidade ao Resumo da Lei do abuso de autoridade para SEFAZ-PA \u2013 Lei 13.869\/2019, vejamos os efeitos da condena\u00e7\u00e3o e as penas restritivas de direito.<\/p>\n\n\n\n<p>Os <strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-cyan-blue-color\">efeitos da condena\u00e7\u00e3o<\/mark> <\/strong>ser\u00e3o<strong> <\/strong>(Art. 4):<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>indenizar o dano causado pelo crime<\/strong>, conforme valor fixado na senten\u00e7a<strong><\/strong><\/li>\n\n\n\n<li>a <strong>inabilita\u00e7\u00e3o para o exerc\u00edcio de cargo<\/strong>, mandato ou fun\u00e7\u00e3o p\u00fablica, pelo per\u00edodo de <strong>1 a 5 anos<\/strong>;<strong>*<\/strong><strong><\/strong><\/li>\n\n\n\n<li>a <strong>perda do cargo<\/strong>, do mandato ou da fun\u00e7\u00e3o p\u00fablica.<strong>*<\/strong><\/li>\n<\/ul>\n\n\n\n<p>As bancas exaustivamente afirmam que a condena\u00e7\u00e3o \u00e9 autom\u00e1tica, cuidado!<\/p>\n\n\n\n<p>*Atente-se que os efeitos s\u00e3o <strong>condicionados \u00e0 ocorr\u00eancia de reincid\u00eancia<\/strong> em crime de abuso de autoridade <strong>e <mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-red-color\">n\u00e3o s\u00e3o autom\u00e1ticos<\/mark><\/strong>, devendo ser declarados motivadamente na senten\u00e7a.<\/p>\n\n\n\n<p>Agora as Penas Restritivas de Direitos.<\/p>\n\n\n\n<p><strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-green-cyan-color\">Penas restritivas de direitos substitutivas das privativas de liberdade<\/mark><\/strong> (Art. 5\u00ba) &nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>presta\u00e7\u00e3o de servi\u00e7os \u00e0 comunidade<\/strong> ou a entidades p\u00fablicas;<\/li>\n\n\n\n<li><strong>suspens\u00e3o do exerc\u00edcio do cargo<\/strong>, da fun\u00e7\u00e3o ou do mandato, pelo prazo de <strong>1 a 6 meses<\/strong>, <strong>com<\/strong> a perda dos vencimentos e das vantagens;<\/li>\n<\/ul>\n\n\n\n<p><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-luminous-vivid-amber-color\"><strong>Obs.:<\/strong> <\/mark>as penas restritivas de direitos <strong>podem ser aplicadas aut\u00f4noma ou cumulativamente<\/strong>.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-sancoes-de-natureza-civil-e-administrativa-nbsp\">San\u00e7\u00f5es de natureza civil e administrativa&nbsp;<\/h2>\n\n\n\n<p>Pessoal, sabemos que as <mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-cyan-blue-color\"><strong>responsabilidades<\/strong> <\/mark>civil e administrativa s\u00e3o <strong>independentes<\/strong> da criminal, <strong>mas <\/strong>lembre-se que <strong>n\u00e3o se pode questionar a exist\u00eancia ou a autoria<\/strong> do fato quando essas quest\u00f5es tenham sido <strong>decididas no ju\u00edzo criminal<\/strong> (Art. 7\u00ba)<\/p>\n\n\n\n<p>Al\u00e9m disso,<mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-green-cyan-color\"> <strong>faz coisa julgada<\/strong><\/mark> (em \u00e2mbito c\u00edvel e administrativo-disciplinar) a senten\u00e7a penal que reconhecer ter sido o ato praticado em (Art. 8\u00ba):<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-red-color\">L<\/mark>eg\u00edtima defesa<\/strong>;<\/li>\n\n\n\n<li><strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-red-color\">E<\/mark>stado de necessidade<\/strong>;<\/li>\n\n\n\n<li><strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-red-color\">E<\/mark>strito cumprimento de dever legal;<\/strong> ou<\/li>\n\n\n\n<li><strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-red-color\">E<\/mark>xerc\u00edcio regular de direito<\/strong><\/li>\n<\/ul>\n\n\n\n<p><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-cyan-bluish-gray-color\"><strong>Bizu<\/strong> <\/mark>\u2013 excludentes de ilicitude: <strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-red-color\">LEEE<\/mark><\/strong><\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-dos-crimes\">Dos Crimes<\/h2>\n\n\n\n<p>Vejamos agora as condutas tipificadas, mas como dica procure palavras como &#8220;manifestamente&#8221;, &#8220;injustificadamente&#8221;, &#8220;excessividade&#8221;, algo que remeta a ser contr\u00e1rio a lei (ex. sem expresso amparo legal).<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-crimes-parte-1\">Crimes \u2013 parte 1<\/h3>\n\n\n\n<p>Vamos \u00e0s condutas criminosas.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-green-cyan-color\"><strong>Decretar medida privativa de liberdade em desacordo com as hip\u00f3teses autorizadas pela lei<\/strong> <\/mark>(Art. 9): deixar de relaxar a pris\u00e3o <strong>manifestamente ilegal<\/strong>; n\u00e3o substituir pris\u00e3o preventiva por medida cautela por liberdade provis\u00f3ria, quando <strong>manifestamente cab\u00edvel<\/strong>; indeferir HC, quando <strong>manifestamente cab\u00edvel.<\/strong><\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-green-cyan-color\">Levar compulsoriamente para pr\u00e1tica de ato processual<\/mark><\/strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-green-cyan-color\"> <\/mark>(Art. 10)<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-green-cyan-color\">Deixar de comunicar injustificadamente pris\u00e3o em flagrante<\/mark><\/strong> (Art. 12)<\/li>\n<\/ul>\n\n\n\n<p><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-purple-color\"><strong>Incorre na mesma pena quem<\/strong>:<\/mark><\/p>\n\n\n\n<p>I &#8211; deixa de comunicar, <strong>imediatamente<\/strong>, a execu\u00e7\u00e3o de pris\u00e3o tempor\u00e1ria ou preventiva \u00e0 autoridade judici\u00e1ria que a decretou;<\/p>\n\n\n\n<p>II &#8211; deixa de comunicar, <strong>imediatamente<\/strong>, a pris\u00e3o de qualquer pessoa e o local onde se encontra \u00e0 sua fam\u00edlia ou \u00e0 pessoa por ela indicada;<\/p>\n\n\n\n<p>III &#8211; deixa de entregar ao preso, no <strong>prazo de 24 horas<\/strong>, a nota de culpa, assinada pela autoridade, com o motivo da pris\u00e3o e os nomes do condutor e das testemunhas;<\/p>\n\n\n\n<p>IV &#8211; prolonga a execu\u00e7\u00e3o de pena privativa de liberdade, de pris\u00e3o tempor\u00e1ria, de pris\u00e3o preventiva, de medida de seguran\u00e7a ou de interna\u00e7\u00e3o, deixando, sem motivo justo e excepcional\u00edssimo, de executar o alvar\u00e1 de soltura imediatamente ap\u00f3s recebido ou de promover a soltura do preso quando esgotado o prazo judicial ou legal.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-green-cyan-color\"><strong>Constranger o preso mediante viol\u00eancia ou amea\u00e7a<\/strong> <\/mark>(Art. 13):<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-green-cyan-color\">Constranger a depor pessoa que deva guardar sigilo<\/mark><\/strong> (Art. 15):<\/li>\n<\/ul>\n\n\n\n<p><strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-purple-color\">Incorre na mesma pena<\/mark><\/strong> quem prossegue com o interrogat\u00f3rio:&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;<\/p>\n\n\n\n<p>I &#8211; de pessoa que tenha <strong>decidido exercer o direito ao sil\u00eancio<\/strong>; ou<\/p>\n\n\n\n<p>II &#8211; de pessoa que tenha <strong>optado por ser assistida por advogado ou defensor p\u00fablico<\/strong>, <strong>sem a presen\u00e7a<\/strong> de seu patrono.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-green-cyan-color\">Deixar de se identificar ao preso por ocasi\u00e3o de pris\u00e3o<\/mark><\/strong> (Art. 16):<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-green-cyan-color\">Submeter o preso a interrogat\u00f3rio policial durante o per\u00edodo de repouso noturno<\/mark><\/strong> (Art. 18) &#8211; <strong>salvo<\/strong> se capturado em flagrante delito ou se ele, devidamente assistido, consentir em prestar declara\u00e7\u00f5es.<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"crimes-parte-2\">Crimes \u2013 parte 2<\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-green-cyan-color\">Impedir envio de pleito de preso \u00e0 autoridade judici\u00e1ria<\/mark><\/strong> (Art. 19):<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-green-cyan-color\"><strong>Impedir entrevista pessoal<\/strong> <\/mark>(Art. 20):<\/li>\n<\/ul>\n\n\n\n<p><strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-purple-color\">Incorre na mesma pena<\/mark><\/strong> quem i<strong>mpede o preso, o r\u00e9u solto ou o investigado de entrevistar-se pessoal e reservadamente com seu advogado ou defen<\/strong>sor, por prazo razo\u00e1vel, antes de audi\u00eancia judicial, e de sentar-se ao seu lado e com ele comunicar-se durante a audi\u00eancia, salvo no curso de interrogat\u00f3rio ou no caso de audi\u00eancia realizada por videoconfer\u00eancia<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Presos de ambos os sexos na mesma cela<\/strong> (Ar. 21)<\/li>\n<\/ul>\n\n\n\n<p><strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-purple-color\">Incorre na mesma pena<\/mark><\/strong> quem mant\u00e9m, <strong>na mesma cela, crian\u00e7a ou adolescente na companhia de maior de idade ou em ambiente inadequado.<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-green-cyan-color\">Invas\u00e3o de im\u00f3vel alheio<\/mark><\/strong> (Art. 22)<\/li>\n<\/ul>\n\n\n\n<p>\u00a7 1\u00ba&nbsp;<strong>Incorre na mesma pena<\/strong>, na forma prevista no&nbsp;<strong>caput<\/strong> deste artigo, quem:<\/p>\n\n\n\n<p>I &#8211; coage algu\u00e9m, mediante viol\u00eancia ou grave amea\u00e7a, a franquear-lhe o acesso a im\u00f3vel ou suas depend\u00eancias;<\/p>\n\n\n\n<p>III &#8211; cumpre <strong>mandado de busca e apreens\u00e3o<\/strong> <strong>domiciliar ap\u00f3s as 21h ou antes das 5h. <\/strong>-&gt; atente-se ao hor\u00e1rio, pois n\u00e3o \u00e9 antes das 6h e depois das 18h, como estamos \u201cacostumados\u201d.<\/p>\n\n\n\n<p>\u00a7 2<mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-purple-color\">\u00ba&nbsp;<strong>N\u00e3o haver\u00e1 crime<\/strong><\/mark> se o ingresso for para <strong>prestar socorro,<\/strong> ou quando houver <strong>fundados ind\u00edcios<\/strong> que indiquem a <strong>necessidade do ingresso em raz\u00e3o de situa\u00e7\u00e3o de flagrante delito ou de desastre<\/strong>.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-green-cyan-color\">Inovar artificiosamente estado de lugar, de coisa ou de pessoa<\/mark><\/strong> (Art. 23):<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-green-cyan-color\"><strong>Constranger funcion\u00e1rio de hospital<\/strong> <\/mark>(art. 24): com o fim de alterar local ou momento de crime<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-crimes-parte-3\">Crimes \u2013 parte 3<\/h3>\n\n\n\n<p>Vejamos as \u00faltimas condutas.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-green-cyan-color\"><strong>Obten\u00e7\u00e3o de prova ilegal<\/strong> <\/mark>(Art. 25)<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-green-cyan-color\">Instaura\u00e7\u00e3o de investiga\u00e7\u00e3o de crime inexistente<\/mark><\/strong> (Art. 27):<\/li>\n<\/ul>\n\n\n\n<p><strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-luminous-vivid-amber-color\">Obs.:<\/mark><\/strong> <strong>N\u00e3o h\u00e1 crime<\/strong> quando se tratar de <strong>sindic\u00e2ncia<\/strong> ou <strong>investiga\u00e7\u00e3o preliminar<\/strong> sum\u00e1ria, devidamente justificada.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-green-cyan-color\">Divulga\u00e7\u00e3o de grava\u00e7\u00e3o ilegal<\/mark><\/strong> (Art. 28)<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-green-cyan-color\">Prestar informa\u00e7\u00e3o falsa<\/mark><\/strong> (Art. 29): fim de prejudicar interesse de investigado<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-green-cyan-color\"><strong>Persecu\u00e7\u00e3o contra inocente<\/strong> <\/mark>(Art. 30): penal, civil ou administrativa sem justa causa fundamentada ou contra quem sabe inocente<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-green-cyan-color\">Estender injustificadamente a investiga\u00e7\u00e3o<\/mark><\/strong> (Art. 31)<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-green-cyan-color\"><strong>Negar autos ao interessado<\/strong> <\/mark>(Art. 32): <strong>ressalvado<\/strong> o acesso a pe\u00e7as relativas a dilig\u00eancias em curso, ou que indiquem a realiza\u00e7\u00e3o de dilig\u00eancias futuras, cujo sigilo seja imprescind\u00edvel<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-green-cyan-color\">Exig\u00eancia e cumprimento de obriga\u00e7\u00e3o sem amparo legal<\/mark><\/strong> (Art. 33)<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-green-cyan-color\"><strong>Decretar indisponibilidade de bens<\/strong> <\/mark>(Art. 36): quantia que <strong>extrapole exacerbadamente o valor<\/strong> estimado para a satisfa\u00e7\u00e3o da d\u00edvida da parte e, ante a demonstra\u00e7\u00e3o, pela parte, da <strong>excessividade da medida<\/strong>, deixar de corrigi-la:<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-green-cyan-color\"><strong>Demora no exame de processo<\/strong> <\/mark>(Art. 37)<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-resumo-estrategico\">Resumo Estrat\u00e9gico<\/h2>\n\n\n\n<p>Para finalizar o Resumo da Lei do abuso de autoridade para SEFAZ-PA \u2013 Lei 13.869\/2019, vamos fechar com um bizu sobre a Lei.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-purple-color\">Penas<\/mark><\/strong>:&nbsp;apenas de&nbsp;<strong>deten\u00e7\u00e3o<\/strong> (6 meses a 2 anos&nbsp;ou&nbsp;1 ano a 4 anos) -&gt; se falar em reclus\u00e3o, j\u00e1 considere errado<\/li>\n\n\n\n<li><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-purple-color\"><strong>Sujeito ativo:<\/strong>\u00a0<\/mark><strong>Agente p\u00fablico<\/strong>, como vimos o rol \u00e9 amplo (membros do executivo, judici\u00e1rio, legislativo e at\u00e9 mesmo transit\u00f3rio e sem remunera\u00e7\u00e3o).<\/li>\n\n\n\n<li><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-purple-color\"><strong>Necess\u00e1rio dolo<\/strong>: <\/mark><strong>Todos os crimes s\u00e3o\u00a0dolosos<\/strong>, ou seja, exigem especial fim de agir.<\/li>\n\n\n\n<li><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-purple-color\"><strong>A\u00e7\u00e3o penal:<\/strong>\u00a0<\/mark><strong>incondicionada<\/strong>, entretanto admite a\u00e7\u00e3o penal privada subsidi\u00e1ria da p\u00fablica<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-consideracoes-finais\">Considera\u00e7\u00f5es Finais<\/h2>\n\n\n\n<p>Pessoal, chegamos ao final do Resumo da Lei do abuso de autoridade para SEFAZ-PA. Espero que o artigo tenha sido \u00fatil.<\/p>\n\n\n\n<p>Trata-se de um tema com bastante quest\u00f5es para treino, assim n\u00e3o deixe de treinar por meio do nosso sistema de quest\u00f5es.<\/p>\n\n\n\n<p><a href=\"https:\/\/concursos.estrategiaeducacional.com.br\/\">Sistema de Quest\u00f5es (SQ) \u2013 Estrat\u00e9gia Concursos<\/a><\/p>\n\n\n\n<p>Gostou do artigo? Siga-nos<\/p>\n\n\n\n<p><a href=\"https:\/\/www.instagram.com\/resumospassarin\/\">https:\/\/www.instagram.com\/resumospassarin\/<\/a><\/p>\n\n\n\n<p class=\"has-text-align-center has-luminous-vivid-amber-color has-black-background-color has-text-color has-background\"> <strong>APROVEITE AS OFERTAS DE NOSSAS ASSINATURAS<\/strong>!<\/p>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-center\" id=\"h-quer-saber-tudo-sobre-concursos-previstos-confira-nossos-artigos\">Quer saber tudo sobre concursos previstos?<br \/>Confira nossos artigos!<\/h2>\n\n\n\n<p class=\"has-text-align-center has-white-color has-black-background-color has-text-color has-background\"><strong><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-abertos\/\" target=\"_blank\" rel=\"noreferrer noopener\">Concursos abertos<\/a><\/strong><\/p>\n\n\n\n<p class=\"has-text-align-center has-white-color has-black-background-color has-text-color has-background\"><strong><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-2022\/\" target=\"_blank\" rel=\"noreferrer noopener\">Concursos 2022<\/a><\/strong><\/p>\n\n\n\n<div class=\"container\" id=\"boxes\">\n  <div class=\"row\">\n\n    <div class=\"col-sm\">\n      <div class=\"estrategia\" id=\"box-assinatura\">\n        <h3 class=\"titulo-assinatura\">Assinatura de Concursos<\/h3>\n        <p class=\"subtitulo-assinatura\">Assinatura de 1 ano ou 2 anos<\/p>\n        <div class=\"box-botao\">\n          <a class=\"btn-assinatura\" target=\"_blank\" href=\"https:\/\/www.estrategiaconcursos.com.br\/assinaturas\/\" role=\"button\" rel=\"noopener noreferrer\">ASSINE AGORA<\/a>\n        <\/div>\n      <\/div>\n     \n    <\/div><\/div><\/div>\n\n\n\n<p>At\u00e9 mais e bons estudos!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ol\u00e1, pessoal. Tudo certo? No artigo de hoje veremos o Resumo da Lei do abuso de autoridade para SEFAZ-PA \u2013 Lei 13.869\/2019. Como estamos em reta final, vamos tentar separar aquilo que de fato tem mais chance de aparecer em sua prova, combinado? Sem mais delongas, vamos l\u00e1. Disposi\u00e7\u00f5es gerais Iniciando o Resumo da Lei [&hellip;]<\/p>\n","protected":false},"author":1763,"featured_media":858050,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"post_tipo":"article","footnotes":""},"categories":[1],"tags":[],"tax_estado":[219977],"class_list":["post-981522","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cursos-e-concursos","tax_estado-pa"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.2 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Resumo da Lei do abuso de autoridade para SEFAZ-PA \u2013 Lei 13.869\/2019<\/title>\n<meta name=\"description\" content=\"Veja neste artigo o Resumo esquem\u00e1tico para a reta final da Lei do abuso de autoridade para SEFAZ-PA \u2013 Lei 13.869\/2019.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/abuso-de-autoridade-para-sefaz-pa\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Resumo da Lei do abuso de autoridade para SEFAZ-PA \u2013 Lei 13.869\/2019\" \/>\n<meta property=\"og:description\" content=\"Veja neste artigo o Resumo esquem\u00e1tico para a reta final da Lei do abuso de autoridade para SEFAZ-PA \u2013 Lei 13.869\/2019.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/abuso-de-autoridade-para-sefaz-pa\/\" \/>\n<meta property=\"og:site_name\" content=\"Estrat\u00e9gia Concursos\" \/>\n<meta property=\"article:published_time\" content=\"2022-03-16T11:07:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-08-31T14:00:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/09\/10084052\/sefa-pa-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1300\" \/>\n\t<meta property=\"og:image:height\" content=\"867\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Leonardo Menezes Passarin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:site\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Leonardo Menezes Passarin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/abuso-de-autoridade-para-sefaz-pa\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/abuso-de-autoridade-para-sefaz-pa\/\"},\"author\":{\"name\":\"Leonardo Menezes Passarin\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/245b44e43eb13f0dbd04a7a078cd0d0d\"},\"headline\":\"Resumo da Lei do abuso de autoridade para SEFAZ-PA \u2013 Lei 13.869\/2019\",\"datePublished\":\"2022-03-16T11:07:00+00:00\",\"dateModified\":\"2023-08-31T14:00:07+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/abuso-de-autoridade-para-sefaz-pa\/\"},\"wordCount\":1517,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/abuso-de-autoridade-para-sefaz-pa\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/09\/10084052\/sefa-pa-1.jpg\",\"articleSection\":[\"Concursos P\u00fablicos\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/abuso-de-autoridade-para-sefaz-pa\/#respond\"]}],\"copyrightYear\":\"2022\",\"copyrightHolder\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/abuso-de-autoridade-para-sefaz-pa\/\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/abuso-de-autoridade-para-sefaz-pa\/\",\"name\":\"Resumo da Lei do abuso de autoridade para SEFAZ-PA \u2013 Lei 13.869\/2019\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/abuso-de-autoridade-para-sefaz-pa\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/abuso-de-autoridade-para-sefaz-pa\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/09\/10084052\/sefa-pa-1.jpg\",\"datePublished\":\"2022-03-16T11:07:00+00:00\",\"dateModified\":\"2023-08-31T14:00:07+00:00\",\"description\":\"Veja neste artigo o Resumo esquem\u00e1tico para a reta final da Lei do abuso de autoridade para SEFAZ-PA \u2013 Lei 13.869\/2019.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/abuso-de-autoridade-para-sefaz-pa\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/abuso-de-autoridade-para-sefaz-pa\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/abuso-de-autoridade-para-sefaz-pa\/#primaryimage\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/09\/10084052\/sefa-pa-1.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/09\/10084052\/sefa-pa-1.jpg\",\"width\":1300,\"height\":867},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/abuso-de-autoridade-para-sefaz-pa\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Resumo da Lei do abuso de autoridade para SEFAZ-PA \u2013 Lei 13.869\/2019\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"name\":\"Estrat\u00e9gia Concursos\",\"description\":\"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.\",\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\",\"name\":\"Estrat\u00e9gia Concursos\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"width\":230,\"height\":60,\"caption\":\"Estrat\u00e9gia Concursos\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/EstratConcursos\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/245b44e43eb13f0dbd04a7a078cd0d0d\",\"name\":\"Leonardo Menezes Passarin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/fc0e5714ceaa97f24e6e6a30eab74ba8a701c2b62f8cab100ffdb22c6d8f42c3?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/fc0e5714ceaa97f24e6e6a30eab74ba8a701c2b62f8cab100ffdb22c6d8f42c3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/fc0e5714ceaa97f24e6e6a30eab74ba8a701c2b62f8cab100ffdb22c6d8f42c3?s=96&d=mm&r=g\",\"caption\":\"Leonardo Menezes Passarin\"},\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/passarin-leonardohotmail-com\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Resumo da Lei do abuso de autoridade para SEFAZ-PA \u2013 Lei 13.869\/2019","description":"Veja neste artigo o Resumo esquem\u00e1tico para a reta final da Lei do abuso de autoridade para SEFAZ-PA \u2013 Lei 13.869\/2019.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.estrategiaconcursos.com.br\/blog\/abuso-de-autoridade-para-sefaz-pa\/","og_locale":"pt_BR","og_type":"article","og_title":"Resumo da Lei do abuso de autoridade para SEFAZ-PA \u2013 Lei 13.869\/2019","og_description":"Veja neste artigo o Resumo esquem\u00e1tico para a reta final da Lei do abuso de autoridade para SEFAZ-PA \u2013 Lei 13.869\/2019.","og_url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/abuso-de-autoridade-para-sefaz-pa\/","og_site_name":"Estrat\u00e9gia Concursos","article_published_time":"2022-03-16T11:07:00+00:00","article_modified_time":"2023-08-31T14:00:07+00:00","og_image":[{"width":1300,"height":867,"url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/09\/10084052\/sefa-pa-1.jpg","type":"image\/jpeg"}],"author":"Leonardo Menezes Passarin","twitter_card":"summary_large_image","twitter_creator":"@EstratConcursos","twitter_site":"@EstratConcursos","twitter_misc":{"Escrito por":"Leonardo Menezes Passarin","Est. tempo de leitura":"8 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/abuso-de-autoridade-para-sefaz-pa\/#article","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/abuso-de-autoridade-para-sefaz-pa\/"},"author":{"name":"Leonardo Menezes Passarin","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/245b44e43eb13f0dbd04a7a078cd0d0d"},"headline":"Resumo da Lei do abuso de autoridade para SEFAZ-PA \u2013 Lei 13.869\/2019","datePublished":"2022-03-16T11:07:00+00:00","dateModified":"2023-08-31T14:00:07+00:00","mainEntityOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/abuso-de-autoridade-para-sefaz-pa\/"},"wordCount":1517,"commentCount":0,"publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/abuso-de-autoridade-para-sefaz-pa\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/09\/10084052\/sefa-pa-1.jpg","articleSection":["Concursos P\u00fablicos"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/abuso-de-autoridade-para-sefaz-pa\/#respond"]}],"copyrightYear":"2022","copyrightHolder":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/abuso-de-autoridade-para-sefaz-pa\/","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/abuso-de-autoridade-para-sefaz-pa\/","name":"Resumo da Lei do abuso de autoridade para SEFAZ-PA \u2013 Lei 13.869\/2019","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/abuso-de-autoridade-para-sefaz-pa\/#primaryimage"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/abuso-de-autoridade-para-sefaz-pa\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/09\/10084052\/sefa-pa-1.jpg","datePublished":"2022-03-16T11:07:00+00:00","dateModified":"2023-08-31T14:00:07+00:00","description":"Veja neste artigo o Resumo esquem\u00e1tico para a reta final da Lei do abuso de autoridade para SEFAZ-PA \u2013 Lei 13.869\/2019.","breadcrumb":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/abuso-de-autoridade-para-sefaz-pa\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/abuso-de-autoridade-para-sefaz-pa\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/abuso-de-autoridade-para-sefaz-pa\/#primaryimage","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/09\/10084052\/sefa-pa-1.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/09\/10084052\/sefa-pa-1.jpg","width":1300,"height":867},{"@type":"BreadcrumbList","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/abuso-de-autoridade-para-sefaz-pa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.estrategiaconcursos.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Resumo da Lei do abuso de autoridade para SEFAZ-PA \u2013 Lei 13.869\/2019"}]},{"@type":"WebSite","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","name":"Estrat\u00e9gia Concursos","description":"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.","publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization","name":"Estrat\u00e9gia Concursos","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","width":230,"height":60,"caption":"Estrat\u00e9gia Concursos"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/EstratConcursos"]},{"@type":"Person","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/245b44e43eb13f0dbd04a7a078cd0d0d","name":"Leonardo Menezes Passarin","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/fc0e5714ceaa97f24e6e6a30eab74ba8a701c2b62f8cab100ffdb22c6d8f42c3?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/fc0e5714ceaa97f24e6e6a30eab74ba8a701c2b62f8cab100ffdb22c6d8f42c3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fc0e5714ceaa97f24e6e6a30eab74ba8a701c2b62f8cab100ffdb22c6d8f42c3?s=96&d=mm&r=g","caption":"Leonardo Menezes Passarin"},"url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/passarin-leonardohotmail-com\/"}]}},"_links":{"self":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/981522","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/users\/1763"}],"replies":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/comments?post=981522"}],"version-history":[{"count":5,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/981522\/revisions"}],"predecessor-version":[{"id":1271778,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/981522\/revisions\/1271778"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media\/858050"}],"wp:attachment":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media?parent=981522"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/categories?post=981522"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tags?post=981522"},{"taxonomy":"tax_estado","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tax_estado?post=981522"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}