{"id":977832,"date":"2022-03-14T08:00:00","date_gmt":"2022-03-14T11:00:00","guid":{"rendered":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?p=977832"},"modified":"2022-03-09T16:55:45","modified_gmt":"2022-03-09T19:55:45","slug":"alesp-resumo-de-nocoes-de-informatica","status":"publish","type":"post","link":"https:\/\/www.estrategiaconcursos.com.br\/blog\/alesp-resumo-de-nocoes-de-informatica\/","title":{"rendered":"ALESP: Resumo de No\u00e7\u00f5es de Inform\u00e1tica para a prova"},"content":{"rendered":"\n<p>Ol\u00e1, tudo bem com voc\u00ea? No artigo de hoje vamos fazer um resumo da disciplina de no\u00e7\u00f5es de inform\u00e1tica para a prova da ALESP. Vamos l\u00e1? <\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/05\/30114326\/cropped-inform%C3%A1tica-1170x800-1-1024x700.jpg\" alt=\"ALESP: Resumo de No\u00e7\u00f5es de Inform\u00e1tica para a prova\" class=\"wp-image-520655\"\/><figcaption>ALESP: Resumo de No\u00e7\u00f5es de Inform\u00e1tica para a prova<\/figcaption><\/figure>\n\n\n\n<p>O&nbsp;<strong>edital <\/strong>da Assembleia Legislativa de S\u00e3o Paulo&nbsp;foi publicado! Est\u00e3o sendo oferecidas&nbsp;<strong>118 vagas<\/strong>&nbsp;para v\u00e1rios cargos de n\u00edvel m\u00e9dio e superior.<\/p>\n\n\n\n<p>A&nbsp;<strong>Funda\u00e7\u00e3o VUNESP<\/strong>&nbsp;\u00e9 a banca organizadora do certame!!<\/p>\n\n\n\n<p>Voc\u00ea est\u00e1 preparado?<\/p>\n\n\n\n<p>No artigo de hoje iremos falar a respeito dos principais pontos da disciplina de No\u00e7\u00f5es Inform\u00e1tica cobrada para os cargos de T\u00e9cnico Legislativo.<\/p>\n\n\n\n<p>Vamos l\u00e1?<\/p>\n\n\n\n<p>Vamos come\u00e7ar por um assunto que despenca nas provas da VUNESP, sabe qual \u00e9 ele?<\/p>\n\n\n\n<p>EXCEL!! Afinal, esse assunto despenca em prova!!<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-excel-alesp-resumo-de-nocoes-de-informatica-para-a-prova\">EXCEL &#8211; ALESP: Resumo de No\u00e7\u00f5es de Inform\u00e1tica para a prova<\/h2>\n\n\n\n<p>Primeiramente, o que \u00e9 o excel?<\/p>\n\n\n\n<p>O Excel \u00e9 um editor de planilhas eletr\u00f4nicas que possui ferramentas para a constru\u00e7\u00e3o de gr\u00e1ficos e ferramentas de c\u00e1lculo.<\/p>\n\n\n\n<p>Por sua vez, o Excel \u00e9 compat\u00edvel com Windows, Mac OS, Android, Windows Phone e iOS. No entanto, o Excel n\u00e3o \u00e9 compat\u00edvel com o Linux.<\/p>\n\n\n\n<p>Os principais formatos do Excel s\u00e3o: <strong>.xlsx e xls<\/strong>.<\/p>\n\n\n\n<p>Voc\u00ea j\u00e1 deve ter escutado falar sobre c\u00e9lulas do Excel, mas o que \u00e9 ela?<\/p>\n\n\n\n<p>A c\u00e9lula trata-se da menor unidade de trabalho do Excel. Assim, uma planilha \u00e9 dividida em c\u00e9lulas, e nessas c\u00e9lulas s\u00e3o inseridos os dados que ser\u00e3o manipulados.<br \/>O Excel divide as suas planilhas em linhas e colunas. Desde a vers\u00e3o do Excel de 2007, cada planilha pode possuir 1.048.576 linhas e 16.384 colunas.<\/p>\n\n\n\n<p>A caixa de nome, que se encontra \u00e0 esquerda e acima da planilha, elenca qual c\u00e9lula est\u00e1 ativa no momento, isto \u00e9, qual c\u00e9lula est\u00e1 pronta para serem inseridos ou exclu\u00eddos os dados.<\/p>\n\n\n\n<p>J\u00e1 a Faixa de Op\u00e7\u00f5es \u00e9 o local em que est\u00e1 o Menu, isto \u00e9, atrav\u00e9s dela os usu\u00e1rios t\u00eam acesso \u00e0s funcionalidades presentes no excel. Al\u00e9m disso, essa Faixa de Op\u00e7\u00f5es \u00e9 personaliz\u00e1vel.<\/p>\n\n\n\n<p>Na faixa de op\u00e7\u00f5es do Excel existem algumas ferramentas de acesso r\u00e1pido, como: Salvar (CTRL + B), Desfazer(CTRL + Z), Refazer(CTRL + Y), al\u00e9m disso, ela tamb\u00e9m pode ser personalizada.<\/p>\n\n\n\n<p>Ademais, para imprimir no excel, pode utilizar o atalho CTRL + P.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"atalhos-do-excel-alesp-resumo-de-nocoes-de-informatica-para-a-prova\">ATALHOS DO EXCEL &#8211; ALESP: Resumo de No\u00e7\u00f5es de Inform\u00e1tica para a prova<\/h2>\n\n\n\n<p>Outros atalhos importantes:<\/p>\n\n\n\n<p>CTRL + Home -&gt; Leva para a c\u00e9lula A1;<\/p>\n\n\n\n<p>CTRL + End -&gt; Leva \u00e0 c\u00e9lula que est\u00e1 na linha mais abaixo e na coluna mais \u00e0 direita preenchida;<\/p>\n\n\n\n<p>Page Down -&gt; Move a tela para baixo;<\/p>\n\n\n\n<p>Page Up -&gt; Move a tela para cima;<\/p>\n\n\n\n<p>Alt+Page Down -&gt; Move para a direita a tela;<\/p>\n\n\n\n<p>Alt+Page Up -&gt; Move para a esquerda a tela;<\/p>\n\n\n\n<p>TAB -&gt; Desloca para a c\u00e9lula a direita;<\/p>\n\n\n\n<p>Shift + TAB -&gt; Desloca para a c\u00e9lula a esquerda;<\/p>\n\n\n\n<p>Esc -&gt; Cancela a sele\u00e7\u00e3o;<\/p>\n\n\n\n<p>Ctrl+Z -&gt; Desfaz a \u00faltima a\u00e7\u00e3o feita;<\/p>\n\n\n\n<p>Ctrl+Y -&gt; Refaz a \u00faltima a\u00e7\u00e3o;<\/p>\n\n\n\n<p>Ctrl+C -&gt; Copia as c\u00e9lulas;<\/p>\n\n\n\n<p>Ctrl+X -&gt; Recorta as c\u00e9lulas;<\/p>\n\n\n\n<p>Ctrl+V -&gt; Cola as c\u00e9lulas;<\/p>\n\n\n\n<p>Alt+F4 -&gt; Fecha a janela do Excel;<\/p>\n\n\n\n<p>F5 -&gt; Abre a janela &#8220;ir para&#8221;.<\/p>\n\n\n\n<p>Aten\u00e7\u00e3o: N\u00e3o confunda pasta de trabalho com planilha, essa \u00e9 uma pegadinha comum das bancas examinadoras.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"excel-parte-iii-alesp-resumo-de-nocoes-de-informatica-para-a-prova\">EXCEL parte III &#8211; ALESP: Resumo de No\u00e7\u00f5es de Inform\u00e1tica para a prova<\/h2>\n\n\n\n<p>Continuando o resumo dos principais pontos do Excel para a sua prova da ALESP:<\/p>\n\n\n\n<p>Intervalo trata-se de um conjunto de c\u00e9lulas consecutivas, sendo que o Excel utiliza o s\u00edmbolo dois pontos (:) para simbolizar esse intervalo entre duas c\u00e9lulas.<\/p>\n\n\n\n<p>Principais funcionalidades:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Formata\u00e7\u00e3o Condicional -&gt; a formata\u00e7\u00e3o condicional verifica o conte\u00fado da c\u00e9lula e aplica o estilo definido pelo usu\u00e1rio para tal conte\u00fado;<\/li><li>Classificar \u2013&gt; utiliza os crit\u00e9rios nas colunas para ordenar os registros das linhas;<\/li><li>Filtrar -&gt; aplica crit\u00e9rios nas colunas a fim de elencar apenas as linhas que atendem ao crit\u00e9rio determinado;<\/li><li>Atingir meta -&gt; o Excel ajusta o valor de outras c\u00e9lulas levando com base o valor determinado para uma das c\u00e9lulas;<\/li><li>Gr\u00e1ficos -&gt;  A partir do guia inserir pode-se criar gr\u00e1ficos no Excel;<\/li><li>Rastrear Dependentes e Rastrear Precedentes -&gt; ao selecionar uma c\u00e9lula, podemos verificar quais c\u00e9lulas ou intervalos a alimentam;<\/li><li>Valida\u00e7\u00e3o de dados -&gt; Controla os dados que podem ser inseridos em uma determinada c\u00e9lula.<\/li><\/ul>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"formula-x-funcao\">F\u00f3rmula x Fun\u00e7\u00e3o<\/h3>\n\n\n\n<p>N\u00e3o confunda o conceito de f\u00f3rmula com o de fun\u00e7\u00e3o. S\u00e3o conceitos diferentes.<\/p>\n\n\n\n<p>Tenha em mente que a f\u00f3rmula trata da sequ\u00eancia de valores constantes, dos operadores e de fun\u00e7\u00f5es pr\u00e9-definidas.<\/p>\n\n\n\n<p>Por sua vez, a fun\u00e7\u00e3o trata-se de uma f\u00f3rmula pr\u00e9-definida que possibilita a execu\u00e7\u00e3o de c\u00e1lculos de maneira simplificada.<\/p>\n\n\n\n<p>Ok, voc\u00ea entendeu que os conceitos s\u00e3o diferentes, mas quais s\u00e3o as fun\u00e7\u00f5es existentes no Excel?<\/p>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"agora-vamos-listar-as-principais-funcoes-existentes-no-excel\">Agora vamos listar as principais fun\u00e7\u00f5es existentes no Excel:<\/h4>\n\n\n\n<ul class=\"wp-block-list\"><li>=SOMA(num1;[num2];\u2026) -&gt; Essa fun\u00e7\u00e3o calcula os n\u00fameros inseridos;<\/li><li>=M\u00c9DIA(num1;[num2];\u2026) -&gt; Calcula a m\u00e9dia aritm\u00e9tica dos n\u00fameros que est\u00e3o inseridos no intervalo;<\/li><li>=MED(num1;[num2];\u2026) -&gt; Verifica a Mediana dos n\u00fameros;<\/li><\/ul>\n\n\n\n<ul class=\"wp-block-list\"><li>=SE(condi\u00e7\u00e3o; valor_se_verdadeiro; valor_se_falso) -&gt; Verifica a condi\u00e7\u00e3o. Sendo assim, se ela for verdadeira, retorna o primeiro valor. Caso seja falsa, retorna o segundo valor;<\/li><\/ul>\n\n\n\n<ul class=\"wp-block-list\"><li>=SOMASE(intervalo; crit\u00e9rios; [intervalo_a_ser_somado]) -&gt; Ao analisar um intervalo, ele analisa uma condi\u00e7\u00e3o. Sendo assim, para as c\u00e9lulas do intervalo no qual a condi\u00e7\u00e3o \u00e9 verdadeira, ele soma o intervalo correspondente;<\/li><li>=CONT.N\u00daM(dado1;[dado2];\u2026) -&gt; Conta quantos dados inseridos no intervalo s\u00e3o n\u00fameros;<\/li><li>=M\u00c1XIMO(num1;[num2];\u2026) -&gt; Verifica o maior n\u00famero;<\/li><li>=M\u00cdNIMO(num1;[num2];\u2026) -&gt; Verifica o menor n\u00famero;<\/li><li>=CONCATENAR(texto1; [texto2];\u2026) -&gt; Junta os textos do intervalo em um \u00fanico;<\/li><li>=ARRED (N\u00famero; Quantidade de D\u00edgitos) -&gt; Arredonda o n\u00famero para um n\u00famero determinado de d\u00edgitos;<\/li><li>=CONT.SE (Intervalo; Crit\u00e9rio) -&gt; Retorna a quantidade de c\u00e9lulas em um conjunto de valores que satisfazem a uma condi\u00e7\u00e3o espec\u00edfica;<\/li><li>=DIA.DA.SEMANA() -&gt; Retorna o dia da semana referente a uma data espec\u00edfica;<\/li><li>=AGORA() -&gt; Retoma a hora e a data atual;<\/li><li>=HOJE() -&gt; Retoma a data atual.<\/li><\/ul>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"formulas\">F\u00f3rmulas<\/h3>\n\n\n\n<p>Ok, mas quanto \u00e0s f\u00f3rmulas, quais s\u00e3o os seus componentes?<\/p>\n\n\n\n<p>Os componentes das f\u00f3rmulas s\u00e3o:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Constantes: Diz respeito a um valor fixo que n\u00e3o \u00e9 modificado pelo Excel;<\/li><li>Operadores: Diz respeito ao tipo de c\u00e1lculo que se quer efetuar em uma f\u00f3rmula, pode ser: adi\u00e7\u00e3o, subtra\u00e7\u00e3o, multiplica\u00e7\u00e3o ou divis\u00e3o;<\/li><li>Refer\u00eancias: Diz respeito a localiza\u00e7\u00e3o de uma c\u00e9lula ou de um intervalo de c\u00e9lulas;<\/li><li>Fun\u00e7\u00f5es: Diz respeito \u00e0s f\u00f3rmulas que s\u00e3o predefinidas para efetuar c\u00e1lculos utilizando argumentos.<\/li><\/ul>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"word-alesp-resumo-de-nocoes-de-informatica-para-a-prova\">WORD &#8211; ALESP: Resumo de No\u00e7\u00f5es de Inform\u00e1tica para a prova<\/h2>\n\n\n\n<p>Provavelmente voc\u00ea j\u00e1 utilizou o Word, n\u00e3o \u00e9?<\/p>\n\n\n\n<p>Mas voc\u00ea sabe para que ele serve?<\/p>\n\n\n\n<p>O Microsoft Word, o famoso Word, trata-se de um editor de documentos, tendo nele v\u00e1rios recursos,  como: diagramas, tabelas, gr\u00e1ficos, entre outros.<br \/>Assim como o Excel, o Word \u00e9 compat\u00edvel com Windows, Mac OS, Android, Windows Phone e<br \/>iOS. Por\u00e9m, o Word n\u00e3o \u00e9 compat\u00edvel com o Linux.4<\/p>\n\n\n\n<p>Os principais formatos do Word s\u00e3o: <strong>.docx e doc<\/strong>.<\/p>\n\n\n\n<p>Assim como no Excel, na faixa de op\u00e7\u00f5es existem algumas ferramentas de acesso r\u00e1pido, como: Salvar (CTRL + B), Desfazer(CTRL + Z), Refazer(CTRL + R), al\u00e9m disso, ela tamb\u00e9m pode ser personalizada.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"atalhos-do-word\">ATALHOS DO WORD <\/h2>\n\n\n\n<p><strong>Grupo Fonte<\/strong><\/p>\n\n\n\n<p>O Grupo Fonte \u00e9 formado por algumas funcionalidades, entre elas:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Negrito \u2013 CTRL + N;<\/li><li>It\u00e1lico \u2013 CTRL + I;<\/li><li>Sublinhado \u2013 CTRL + S;<\/li><li>CTRL + SHIFT + F -&gt; seleciona uma fonte para o texto;<\/li><li>CTRL + SHIFT + P -&gt; muda o tamanho do texto;<\/li><li>CTRL + SHIFT + &gt; -&gt; aumenta o texto;<\/li><li>CTRL + SHIFT + &lt; -&gt; diminui o texto.<\/li><\/ul>\n\n\n\n<p><strong>Grupo Par\u00e1grafo<\/strong><\/p>\n\n\n\n<p>O Grupo Par\u00e1grafo \u00e9 formado por algumas funcionalidades, entre elas:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>CTRL + E \u2013&gt; centraliza o texto;<\/li><li>CTRL + G \u2013&gt; alinha o texto \u00e0 direita;<\/li><li>CTRL + Q \u2013&gt; alinha o texto \u00e0 esquerda;<\/li><li>CTRL + J \u2013&gt; justifica o texto.<\/li><\/ul>\n\n\n\n<p>Outros atalhos do Word: <\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>CTRL + A -&gt; abre um documento;<\/li><li>CTRL + C -&gt; copia o texto relacionado;<\/li><li>CTRL + E -&gt; centraliza o texto;<\/li><li>CTRL + B -&gt; salva um documento;<\/li><li>CTRL + J -&gt; alinha o texto de modo justificado;<\/li><li>CTRL + F -&gt; aumenta o espa\u00e7amento;<\/li><li>CTRL + K -&gt; adiciona um hiperlink;<\/li><li>CTRL + L -&gt; abre a fun\u00e7\u00e3o de localizar;<\/li><li>F1 -&gt; obt\u00e9m ajuda;<\/li><li>F4 -&gt; repete a \u00faltima a\u00e7\u00e3o;<\/li><li>F7 -&gt; escolhe o comando ortografia.<\/li><\/ul>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"windows-alesp-resumo-de-nocoes-de-informatica-para-a-prova\">WINDOWS &#8211; ALESP: Resumo de No\u00e7\u00f5es de Inform\u00e1tica para a prova<\/h2>\n\n\n\n<p>O Windows al\u00e9m de controlar todas as janelas e cada parte do computador, ele supervisiona todos os programas em execu\u00e7\u00e3o quando ligamos o computador. Sua fun\u00e7\u00e3o \u00e9 garantir que todos os programas funcionem em perfeita ordem. <\/p>\n\n\n\n<p>O Windows 10 \u00e9 a vers\u00e3o do Microsoft Windows para utiliza\u00e7\u00e3o em computadores pessoais, o que inclui os computadores dom\u00e9sticos e os empresariais, al\u00e9m dos laptops, PCs, entre outros.<\/p>\n\n\n\n<p>As vers\u00f5es dos Windows orientadas para o usu\u00e1rio dom\u00e9stico eram compat\u00edveis com os sistemas de arquivos denominados FAT \u2013 File Allocation Table (FAT 16 e FAT 32). No entanto, enquanto o Windows para servidores era compat\u00edvel com o NTFS \u2013 New Technology File System.<br \/>Por\u00e9m, o NTFS tornou-se o sistema de arquivos preferencial do Windows desde o Windows XP. <\/p>\n\n\n\n<p>Aten\u00e7\u00e3o: No Windows a \u00e1rea de trabalho (ou desktop) \u00e9 como se fosse uma mesa de trabalho virtual que aparece no fundo da tela do monitor.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"elementos-existentes-no-windows\">Elementos existentes no Windows:<\/h4>\n\n\n\n<ul class=\"wp-block-list\"><li>\u00c1rea de Trabalho -&gt; \u00c9 a tela principal existente no sistema operacional;<\/li><li>Lixeira -&gt; \u00c9 onde os arquivos exclu\u00eddos ficam antes de apag\u00e1-los definitivamente;<\/li><li>\u00c1rea de Transfer\u00eancia -&gt; trata-se da mem\u00f3ria respons\u00e1vel por copiar ou recortar arquivos;<\/li><li>Gerenciador de Tarefas -&gt; \u00c9 respons\u00e1vel por finalizar os processos travados, o famoso Ctrl+Shift+Esc;<\/li><li>Explorador de arquivos -&gt; \u00e9 respons\u00e1vel por navegar pelos arquivos e pastas;<\/li><li>Windows Defender Firewall -&gt; \u00e9 o antiv\u00edrus e firewall padr\u00e3o existente no Windows.<\/li><\/ul>\n\n\n\n<p>Bot\u00f5es de dimensionamento do Windows:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Minimizar -&gt; este bot\u00e3o \u00e9 respons\u00e1vel por diminuir o tamanho da janela para que ela seja representada somente como um bot\u00e3o na barra de tarefas;<\/li><li>Restaurar tamanho -&gt; a janela volta para o tamanho original;<\/li><li>Maximizar -&gt; aumenta o tamanho da janela, fazendo com que ela preencha a \u00e1rea de trabalho por completo;<\/li><li>Fechar -&gt; fecha a janela.<\/li><\/ul>\n\n\n\n<p><strong>Principais atalhos do Windows:<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Windows +A -&gt; Abre a central de a\u00e7\u00f5es;<\/li><li>Windows +M -&gt; Minimiza as janelas;<\/li><li>Windows +F -&gt; Utilizado para pesquisa um arquivo;<\/li><li>Shift + Del -&gt; Apaga um arquivo definitivamente, sem ir para a lixeira;<\/li><li>Ctrl + Shift + Esc -&gt; Abre o gerenciador de tarefas;<\/li><li>Alt + F4 -&gt; Fecha o aplicativo.<\/li><\/ul>\n\n\n\n<p>Espero que tenham gostado do artigo do artigo de hoje e boa prova!<\/p>\n\n\n\n<p>Um abra\u00e7o e bons estudos!<\/p>\n\n\n\n<p>Leonardo Mathias <\/p>\n\n\n\n<p>@profleomathias<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-wp-embed is-provider-estrategia-concursos wp-block-embed-estrategia-concursos\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"wp-embedded-content\" data-secret=\"dGdkfnwPCv\"><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/ciclo-x-cronograma-de-estudo-qual-funciona-melhor-para-mim\/\">Ciclo x Cronograma de Estudo: Qual funciona melhor para mim?<\/a><\/blockquote><iframe loading=\"lazy\" class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; clip: rect(1px, 1px, 1px, 1px);\" title=\"&#8220;Ciclo x Cronograma de Estudo: Qual funciona melhor para mim?&#8221; &#8212; Estrat\u00e9gia Concursos\" src=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/ciclo-x-cronograma-de-estudo-qual-funciona-melhor-para-mim\/embed\/#?secret=uJzIZ4KTEY#?secret=dGdkfnwPCv\" data-secret=\"dGdkfnwPCv\" width=\"500\" height=\"282\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe>\n<\/div><figcaption><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/ciclo-x-cronograma-de-estudo-qual-funciona-melhor-para-mim\/\">https:\/\/www.estrategiaconcursos.com.br\/blog\/ciclo-x-cronograma-de-estudo-qual-funciona-melhor-para-mim\/<\/a><\/figcaption><\/figure>\n\n\n\n<p><a href=\"https:\/\/www.al.sp.gov.br\/\">https:\/\/www.al.sp.gov.br\/<\/a><\/p>\n\n\n\n<h2 class=\"has-text-align-center wp-block-heading\" id=\"h-cursos-e-assinaturas\">Cursos e Assinaturas <\/h2>\n\n\n\n<p>Prepare-se com o melhor material e com quem mais aprova em Concursos P\u00fablicos em todo o pa\u00eds!<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p class=\"has-text-align-center has-white-color has-vivid-purple-background-color has-text-color has-background\"><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-abertos\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Concursos abertos<\/strong><\/a><\/p>\n\n\n\n<p class=\"has-text-align-center has-white-color has-vivid-purple-background-color has-text-color has-background\"><strong><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-2022\/\" target=\"_blank\" rel=\"noreferrer noopener\">Concursos 2022<\/a><\/strong><\/p>\n\n\n\n<div class=\"container\" id=\"boxes\">\n  <div class=\"row\">\n    <div class=\"col-sm\">\n      <div class=\"estrategia\" id=\"box-assinatura\">\n        <h3 class=\"titulo-assinatura\">Assinatura de Concursos<\/h3>\n        <p class=\"subtitulo-assinatura\">Assinatura de 1 ano ou 2 anos<\/p>\n        <div class=\"box-botao\">\n          <a class=\"btn-assinatura\" target=\"_blank\" href=\"https:\/\/www.estrategiaconcursos.com.br\/assinaturas\/\" role=\"button\" rel=\"noopener noreferrer\">ASSINE AGORA<\/a>\n        <\/div>\n      <\/div>\n      \n    <\/div><\/div><\/div>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ol\u00e1, tudo bem com voc\u00ea? No artigo de hoje vamos fazer um resumo da disciplina de no\u00e7\u00f5es de inform\u00e1tica para a prova da ALESP. Vamos l\u00e1? O&nbsp;edital da Assembleia Legislativa de S\u00e3o Paulo&nbsp;foi publicado! Est\u00e3o sendo oferecidas&nbsp;118 vagas&nbsp;para v\u00e1rios cargos de n\u00edvel m\u00e9dio e superior. A&nbsp;Funda\u00e7\u00e3o VUNESP&nbsp;\u00e9 a banca organizadora do certame!! Voc\u00ea est\u00e1 preparado? [&hellip;]<\/p>\n","protected":false},"author":773,"featured_media":50570,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"post_tipo":"article","footnotes":""},"categories":[2017],"tags":[],"tax_estado":[219989],"class_list":["post-977832","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-concursos-legislativos","tax_estado-sp"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.2 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>ALESP: Resumo de No\u00e7\u00f5es de Inform\u00e1tica para a prova<\/title>\n<meta name=\"description\" content=\"ALESP: Resumo de No\u00e7\u00f5es de Inform\u00e1tica para a prova, como gabaritar essa disciplina para o novo concurso da Assembleia Legislativa de SP\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/alesp-resumo-de-nocoes-de-informatica\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ALESP: Resumo de No\u00e7\u00f5es de Inform\u00e1tica para a prova\" \/>\n<meta property=\"og:description\" content=\"ALESP: Resumo de No\u00e7\u00f5es de Inform\u00e1tica para a prova, como gabaritar essa disciplina para o novo concurso da Assembleia Legislativa de SP\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/alesp-resumo-de-nocoes-de-informatica\/\" \/>\n<meta property=\"og:site_name\" content=\"Estrat\u00e9gia Concursos\" \/>\n<meta property=\"article:published_time\" content=\"2022-03-14T11:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2016\/09\/25210722\/concurso-alesp.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"580\" \/>\n\t<meta property=\"og:image:height\" content=\"385\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Leonardo Mathias\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:site\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Leonardo Mathias\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"10 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/alesp-resumo-de-nocoes-de-informatica\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/alesp-resumo-de-nocoes-de-informatica\/\"},\"author\":{\"name\":\"Leonardo Mathias\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/ffa1e327b35698a5329b293a0627bd55\"},\"headline\":\"ALESP: Resumo de No\u00e7\u00f5es de Inform\u00e1tica para a prova\",\"datePublished\":\"2022-03-14T11:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/alesp-resumo-de-nocoes-de-informatica\/\"},\"wordCount\":2021,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/alesp-resumo-de-nocoes-de-informatica\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2016\/09\/25210722\/concurso-alesp.jpg\",\"articleSection\":[\"Legislativo\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/alesp-resumo-de-nocoes-de-informatica\/#respond\"]}],\"copyrightYear\":\"2022\",\"copyrightHolder\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/alesp-resumo-de-nocoes-de-informatica\/\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/alesp-resumo-de-nocoes-de-informatica\/\",\"name\":\"ALESP: Resumo de No\u00e7\u00f5es de Inform\u00e1tica para a prova\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/alesp-resumo-de-nocoes-de-informatica\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/alesp-resumo-de-nocoes-de-informatica\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2016\/09\/25210722\/concurso-alesp.jpg\",\"datePublished\":\"2022-03-14T11:00:00+00:00\",\"description\":\"ALESP: Resumo de No\u00e7\u00f5es de Inform\u00e1tica para a prova, como gabaritar essa disciplina para o novo concurso da Assembleia Legislativa de SP\",\"breadcrumb\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/alesp-resumo-de-nocoes-de-informatica\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/alesp-resumo-de-nocoes-de-informatica\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/alesp-resumo-de-nocoes-de-informatica\/#primaryimage\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2016\/09\/25210722\/concurso-alesp.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2016\/09\/25210722\/concurso-alesp.jpg\",\"width\":580,\"height\":385,\"caption\":\"ALESP: Como gabaritar No\u00e7\u00f5es de Inform\u00e1tica na prova\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/alesp-resumo-de-nocoes-de-informatica\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ALESP: Resumo de No\u00e7\u00f5es de Inform\u00e1tica para a prova\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"name\":\"Estrat\u00e9gia Concursos\",\"description\":\"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.\",\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\",\"name\":\"Estrat\u00e9gia Concursos\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"width\":230,\"height\":60,\"caption\":\"Estrat\u00e9gia Concursos\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/EstratConcursos\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/ffa1e327b35698a5329b293a0627bd55\",\"name\":\"Leonardo Mathias\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/f02a0a4304a1537239604f568c9b6a69a3a7bbd6a5033b760cb4a5697f00295b?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/f02a0a4304a1537239604f568c9b6a69a3a7bbd6a5033b760cb4a5697f00295b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/f02a0a4304a1537239604f568c9b6a69a3a7bbd6a5033b760cb4a5697f00295b?s=96&d=mm&r=g\",\"caption\":\"Leonardo Mathias\"},\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/leonardomathiasestrategiaconcursos-com-br\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"ALESP: Resumo de No\u00e7\u00f5es de Inform\u00e1tica para a prova","description":"ALESP: Resumo de No\u00e7\u00f5es de Inform\u00e1tica para a prova, como gabaritar essa disciplina para o novo concurso da Assembleia Legislativa de SP","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.estrategiaconcursos.com.br\/blog\/alesp-resumo-de-nocoes-de-informatica\/","og_locale":"pt_BR","og_type":"article","og_title":"ALESP: Resumo de No\u00e7\u00f5es de Inform\u00e1tica para a prova","og_description":"ALESP: Resumo de No\u00e7\u00f5es de Inform\u00e1tica para a prova, como gabaritar essa disciplina para o novo concurso da Assembleia Legislativa de SP","og_url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/alesp-resumo-de-nocoes-de-informatica\/","og_site_name":"Estrat\u00e9gia Concursos","article_published_time":"2022-03-14T11:00:00+00:00","og_image":[{"width":580,"height":385,"url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2016\/09\/25210722\/concurso-alesp.jpg","type":"image\/jpeg"}],"author":"Leonardo Mathias","twitter_card":"summary_large_image","twitter_creator":"@EstratConcursos","twitter_site":"@EstratConcursos","twitter_misc":{"Escrito por":"Leonardo Mathias","Est. tempo de leitura":"10 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/alesp-resumo-de-nocoes-de-informatica\/#article","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/alesp-resumo-de-nocoes-de-informatica\/"},"author":{"name":"Leonardo Mathias","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/ffa1e327b35698a5329b293a0627bd55"},"headline":"ALESP: Resumo de No\u00e7\u00f5es de Inform\u00e1tica para a prova","datePublished":"2022-03-14T11:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/alesp-resumo-de-nocoes-de-informatica\/"},"wordCount":2021,"commentCount":0,"publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/alesp-resumo-de-nocoes-de-informatica\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2016\/09\/25210722\/concurso-alesp.jpg","articleSection":["Legislativo"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/alesp-resumo-de-nocoes-de-informatica\/#respond"]}],"copyrightYear":"2022","copyrightHolder":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/alesp-resumo-de-nocoes-de-informatica\/","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/alesp-resumo-de-nocoes-de-informatica\/","name":"ALESP: Resumo de No\u00e7\u00f5es de Inform\u00e1tica para a prova","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/alesp-resumo-de-nocoes-de-informatica\/#primaryimage"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/alesp-resumo-de-nocoes-de-informatica\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2016\/09\/25210722\/concurso-alesp.jpg","datePublished":"2022-03-14T11:00:00+00:00","description":"ALESP: Resumo de No\u00e7\u00f5es de Inform\u00e1tica para a prova, como gabaritar essa disciplina para o novo concurso da Assembleia Legislativa de SP","breadcrumb":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/alesp-resumo-de-nocoes-de-informatica\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/alesp-resumo-de-nocoes-de-informatica\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/alesp-resumo-de-nocoes-de-informatica\/#primaryimage","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2016\/09\/25210722\/concurso-alesp.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2016\/09\/25210722\/concurso-alesp.jpg","width":580,"height":385,"caption":"ALESP: Como gabaritar No\u00e7\u00f5es de Inform\u00e1tica na prova"},{"@type":"BreadcrumbList","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/alesp-resumo-de-nocoes-de-informatica\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.estrategiaconcursos.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"ALESP: Resumo de No\u00e7\u00f5es de Inform\u00e1tica para a prova"}]},{"@type":"WebSite","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","name":"Estrat\u00e9gia Concursos","description":"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.","publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization","name":"Estrat\u00e9gia Concursos","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","width":230,"height":60,"caption":"Estrat\u00e9gia Concursos"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/EstratConcursos"]},{"@type":"Person","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/ffa1e327b35698a5329b293a0627bd55","name":"Leonardo Mathias","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/f02a0a4304a1537239604f568c9b6a69a3a7bbd6a5033b760cb4a5697f00295b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f02a0a4304a1537239604f568c9b6a69a3a7bbd6a5033b760cb4a5697f00295b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f02a0a4304a1537239604f568c9b6a69a3a7bbd6a5033b760cb4a5697f00295b?s=96&d=mm&r=g","caption":"Leonardo Mathias"},"url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/leonardomathiasestrategiaconcursos-com-br\/"}]}},"_links":{"self":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/977832","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/users\/773"}],"replies":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/comments?post=977832"}],"version-history":[{"count":10,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/977832\/revisions"}],"predecessor-version":[{"id":985933,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/977832\/revisions\/985933"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media\/50570"}],"wp:attachment":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media?parent=977832"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/categories?post=977832"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tags?post=977832"},{"taxonomy":"tax_estado","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tax_estado?post=977832"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}