{"id":943932,"date":"2022-01-17T08:21:00","date_gmt":"2022-01-17T11:21:00","guid":{"rendered":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?p=943932"},"modified":"2022-01-12T16:17:52","modified_gmt":"2022-01-12T19:17:52","slug":"voz-passiva-e-passividade","status":"publish","type":"post","link":"https:\/\/www.estrategiaconcursos.com.br\/blog\/voz-passiva-e-passividade\/","title":{"rendered":"Voz Passiva e Passividade"},"content":{"rendered":"\n<p>Ol\u00e1, concurseiros, tudo bem? Sabemos que a L\u00edngua Portuguesa \u00e9 uma disciplina-chave em todos os concursos. Quem a domina, certamente sai com grande vantagem na frente dos outros candidatos. Um dos assuntos que gera grande d\u00favida nos alunos \u00e9 sobre <strong>voz passiva e passividade<\/strong>. <\/p>\n\n\n\n<p>Voc\u00ea sabe o que s\u00e3o? Sabe a diferen\u00e7a entre elas?<\/p>\n\n\n\n<p>Com tantos certames em aberto, o concurseiro deve estar com o conhecimento afiado.<\/p>\n\n\n\n<p>Neste texto, pretendemos fazer um breve resumo para que voc\u00ea aprenda a diferenciar as vozes verbais e detone as bancas. Vamos l\u00e1?<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/01\/10221915\/portrait-pensive-young-girl-making-notes-1024x683.jpg\" alt=\"Voz Passiva e Passividade\" class=\"wp-image-943936\" srcset=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/01\/10221915\/portrait-pensive-young-girl-making-notes-1024x683.jpg 1024w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/01\/10221915\/portrait-pensive-young-girl-making-notes-300x200.jpg 300w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/01\/10221915\/portrait-pensive-young-girl-making-notes-768x512.jpg 768w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/01\/10221915\/portrait-pensive-young-girl-making-notes-1536x1024.jpg 1536w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/01\/10221915\/portrait-pensive-young-girl-making-notes-2048x1365.jpg 2048w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/01\/10221915\/portrait-pensive-young-girl-making-notes-610x407.jpg 610w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption>Voz Passiva e Passividade<\/figcaption><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-o-que-sao-vozes-verbais\"><strong>O que s\u00e3o vozes verbais?<\/strong><\/h2>\n\n\n\n<p>Antes de adentrarmos no tema propriamente dito, precisamos relembrar alguns conceitos iniciais deste t\u00f3pico, pois n\u00e3o \u00e9 poss\u00edvel falar sobre voz passiva e passividade sem recapitular o que s\u00e3o vozes verbais.<\/p>\n\n\n\n<p>Desta forma, <strong>voz verbal<\/strong> pode ser definida como <em>&#8220;a forma que o verbo se encontra para indicar sua rela\u00e7\u00e3o com o sujeito&#8221;,<\/em> ou seja, ela exerce a fun\u00e7\u00e3o de  informar a rela\u00e7\u00e3o entre a a\u00e7\u00e3o e os seus respectivos participantes, indicando se o sujeito \u00e9 agente ou paciente na a\u00e7\u00e3o expressa pelo verbo.<\/p>\n\n\n\n<p>Na L\u00edngua Portuguesa, existem <strong>tr\u00eas tipos <\/strong>de vozes verbais. S\u00e3o elas:<\/p>\n\n\n\n<ol class=\"wp-block-list\" type=\"1\"><li><strong>Voz ativa<\/strong><\/li><li><strong>Voz passiva<\/strong><\/li><li><strong>Voz reflexiva<\/strong><\/li><\/ol>\n\n\n\n<p>Vamos analisar rapidamente uma a uma?<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Voz ativa<\/strong><\/h2>\n\n\n\n<p>Este tipo de constru\u00e7\u00e3o \u00e9 a mais recorrente na L\u00edngua Portuguesa. Afinal,&nbsp;ocorre quando o<strong> sujeito<\/strong>, chamado de agente,<strong> pratica a a\u00e7\u00e3o expressa pelo verbo<\/strong>. Ela \u00e9 a mais simples de se identificar. Vamos ver alguns exemplos:<\/p>\n\n\n\n<p>(1) O concurseiro <strong>acertou as quest\u00f5es.&nbsp;<\/strong><\/p>\n\n\n\n<p>(2) Ele<strong> escreveu a carta.<\/strong><\/p>\n\n\n\n<p>(3) Eles <strong>forneceram abrigo<\/strong> aos necessitados.<\/p>\n\n\n\n<p>Atente que nas tr\u00eas estruturas acima, reparem que os sujeitos\/agentes (<em>&#8220;O concurseiro&#8221;,<\/em> <em>&#8220;Ele&#8221;<\/em>, <em>&#8220;Eles&#8221;<\/em>) praticaram a a\u00e7\u00e3o expressa pelo verbo (<em>&#8220;Acertou as quest\u00f5es&#8221;,<\/em> <em>&#8220;Escreveu a carta&#8221;<\/em> e <em>&#8220;Forneceram abrigo&#8221;<\/em>).<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Voz passiva<\/strong><\/h2>\n\n\n\n<p>Nas ora\u00e7\u00f5es indicativas de voz passiva, <strong>o sujeito<\/strong>, chamado de paciente, <strong>sofre ou recebe a a\u00e7\u00e3o<\/strong>. Esta voz verbal pode ser subdivida em dois subtipos, conforme veremos a seguir.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Voz Passiva Anal\u00edtica<\/strong><\/h3>\n\n\n\n<p>Sua principal caracter\u00edstica \u00e9, em geral, a constru\u00e7\u00e3o feita atrav\u00e9s de<strong> locu\u00e7\u00e3o verbal formada por ser\/estar\/ficar + partic\u00edpio do verbo principal.<\/strong> Normalmente, o sujeito \u00e9 paciente, em outras palavras, \u00e9 ele quem sofre a a\u00e7\u00e3o. <\/p>\n\n\n\n<p>Al\u00e9m disso, a voz passiva anal\u00edtica \u00e9 marcada pela presen\u00e7a do <strong>agente da passiva<\/strong>, que pode ser definido como o <strong>termo da ora\u00e7\u00e3o que pratica a a\u00e7\u00e3o verbal <\/strong>quando o verbo se encontra na voz passiva. Normalmente <strong>vem acompanhado pela preposi\u00e7\u00e3o &#8220;por&#8221; e suas varia\u00e7\u00f5es (pelo, pelos, pela, pelas).<\/strong><\/p>\n\n\n\n<p>Em geral, a estrutura da passiva anal\u00edtica aparece da seguinte forma: <\/p>\n\n\n\n<p><strong>Sujeito Paciente + Verbo Auxiliar + Partic\u00edpio do Verbo Principal + Preposi\u00e7\u00e3o + Agente da Passiva.<\/strong><\/p>\n\n\n\n<p>Para ficar mais claro, vamos conferir <strong>alguns exemplos<\/strong>:<\/p>\n\n\n\n<p>(1) Os resultados da pesquisa <strong>foram apresentados<\/strong> pela Institui\u00e7\u00e3o.<\/p>\n\n\n\n<p>(2) A casa <strong>est\u00e1 cercada<\/strong> por bandidos.<\/p>\n\n\n\n<p>(3) Os meninos <strong>ser\u00e3o conduzidos <\/strong>pelo mestre.<\/p>\n\n\n\n<p>Observem que, nas tr\u00eas constru\u00e7\u00f5es acima, os sujeitos\/pacientes (<em>&#8220;Os resultados&#8221;,<\/em> <em>&#8220;A casa&#8221;&#8221;<\/em>, <em>&#8220;Os meninos&#8221;<\/em>) sofrem\/recebem a a\u00e7\u00e3o expressa pelo verbo (<em>&#8220;Foram apresentados&#8221;,<\/em> <em>&#8220;Est\u00e1 cercada&#8221;<\/em> e <em>&#8220;Ser\u00e3o conduzidos&#8221;<\/em>). <\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Voz Passiva Sint\u00e9tica<\/strong><strong><\/strong><\/h3>\n\n\n\n<p>Na<strong> passiva sint\u00e9tica<\/strong>, tamb\u00e9m conhecida por <strong>pronominal<\/strong>, a forma\u00e7\u00e3o se d\u00e1 pelo <strong>pronome \u201cse\u201d<\/strong>, que exerce a <strong>fun\u00e7\u00e3o apassivadora.<\/strong><\/p>\n\n\n\n<p>Nesse tipo de constru\u00e7\u00e3o,<strong> n\u00e3o h\u00e1 verbo auxiliar<\/strong>. Por este motivo, alguns gram\u00e1ticos a denominam passiva sint\u00e9tica. Ao contr\u00e1rio da voz anal\u00edtica, o agente da passiva n\u00e3o se faz presente. <\/p>\n\n\n\n<p>A estrutura da passiva sint\u00e9tica segue a seguinte estrutura:<\/p>\n\n\n\n<p><strong>Verbo Transitivo + Pronome Se + Sujeito Paciente<\/strong><\/p>\n\n\n\n<p>Vamos novamente aos <strong>exemplos<\/strong> para clarificar as ideias:<\/p>\n\n\n\n<p>(1) <strong>Apresentaram-se <\/strong>os resultados da pesquisa.<\/p>\n\n\n\n<p>(2) Obras de arte raras <strong>salvaram-se<\/strong> no inc\u00eandio do museu.<\/p>\n\n\n\n<p>(3) <strong>Praticaram-se<\/strong> boas a\u00e7\u00f5es.<\/p>\n\n\n\n<p>Nas tr\u00eas constru\u00e7\u00f5es acima, os sujeitos\/pacientes (<em>&#8220;Os resultados da pesquisa&#8221;,<\/em> <em>&#8220;Obras de arte raras&#8221;&#8221;<\/em>, <em>&#8220;Boas a\u00e7\u00f5es&#8221;<\/em>) sofrem\/recebem a a\u00e7\u00e3o expressa pelo verbo (<em>&#8220;Apresentaram-se&#8221;<\/em>, &#8220;Salvaram-se&#8221; e &#8220;Praticaram-se&#8221;). <\/p>\n\n\n\n<p><strong><span class=\"has-inline-color has-vivid-red-color\">TOME NOTA:<\/span><\/strong> Para saber se o &#8220;se&#8221; \u00e9 uma part\u00edcula apassivadora, passe a voz passiva sint\u00e9tica para anal\u00edtica, ou seja, se a reescritura fizer sentido, o &#8220;se&#8221; \u00e9 pronome apassivador. Veja:<\/p>\n\n\n\n<p>&#8220;<strong>Apresentaram-se<\/strong> os resultados da pesquisa&#8221;      X       &#8220;Os resultados da pesquisa <strong>foram apresentados<\/strong>&#8220;<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Voz Reflexiva<\/strong><\/h2>\n\n\n\n<p>A voz reflexiva ocorre quando o <strong>verbo<\/strong> indica uma<strong> a\u00e7\u00e3o praticada e sofrida pelo pr\u00f3prio sujeito<\/strong>, isto \u00e9,  o sujeito que pratica, ao mesmo tempo, sofre a a\u00e7\u00e3o verbal. <\/p>\n\n\n\n<p>Para ilustrar, podemos citar como exemplos:<\/p>\n\n\n\n<p>(1) A mulher<strong> se feriu<\/strong> com a faca.<\/p>\n\n\n\n<p>(2) O homem <strong>se barbeou <\/strong>muit\u00edssimo bem.<\/p>\n\n\n\n<p>(3) Maria <strong>se cortou<\/strong> com a faca.<\/p>\n\n\n\n<p>Repare que, nas frases acima, <em>&#8220;A mulher&#8221;<\/em>,<em>&#8220;O homem&#8221;<\/em> e <em>&#8220;Maria&#8221; <\/em>s\u00e3o os sujeitos que praticam e recebem a a\u00e7\u00e3o concomitantemente (<em>&#8220;se feriu&#8221;<\/em>, <em>&#8220;se barbeou&#8221;<\/em> e <em>&#8220;se cortou&#8221;<\/em>). Desta forma, o sujeito da voz reflexiva \u00e9 um <strong>sujeito agente\/paciente.<\/strong><\/p>\n\n\n\n<p><strong><span class=\"has-inline-color has-vivid-red-color\">DICA R\u00c1PIDA: <\/span><\/strong>Se, diante de uma quest\u00e3o, ainda restar d\u00favidas, pergunte quem praticou e quem sofreu a a\u00e7\u00e3o. Vamos ver?<\/p>\n\n\n\n<p>&#8220;A mulher <strong>se feriu <\/strong>com a faca&#8221;.<\/p>\n\n\n\n<p>a) Quem se feriu? A mulher.<\/p>\n\n\n\n<p>b) Quem foi ferida? A mulher.<\/p>\n\n\n\n<p>Simples, n\u00e9?<\/p>\n\n\n\n<p>Normalmente, verbos que podem ser realizados tanto em outra pessoa quanto em si mesmo representam voz reflexiva, quando escoltado de pronome reflexivo.<\/p>\n\n\n\n<p><span class=\"has-inline-color has-vivid-red-color\"><strong>ATEN\u00c7\u00c3O: <\/strong><\/span>Al\u00e9m da voz reflexiva propriamente dita, h\u00e1 em nossa gram\u00e1tica a chamada <strong>voz reflexiva rec\u00edproca<\/strong>. Ela ocorre, normalmente, quando h\u00e1 dois sujeitos praticando a mesma a\u00e7\u00e3o verbal um no outro, como por exemplo: <em>&#8220;Eles <strong>se entreolharam<\/strong> amorosamente&#8221; ou &#8220;N\u00f3s <strong>nos abra\u00e7amos<\/strong>&#8220;.<\/em><\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Voz Passiva x Passividade<\/strong><strong><\/strong><\/h2>\n\n\n\n<p>Agora que j\u00e1 relembramos o b\u00e1sico sobre as vozes verbais, vamos destrinchar&nbsp;o assunto principal do nosso artigo e entender, de uma vez por todas, qual a diferen\u00e7a entre <strong>voz passiva e passividade<\/strong>.<\/p>\n\n\n\n<p>Contudo, antes de nos aprofundar, cabe ressaltar que este tema \u00e9 bastante pol\u00eamico entre os te\u00f3ricos e, embora seja importante saber diferenci\u00e1-lo, as bancas costumam ser mais conservadoras em suas quest\u00f5es que tratam das vozes verbais, n\u00e3o abordando este t\u00f3pico em espec\u00edfico com bastante frequ\u00eancia.<\/p>\n\n\n\n<p>Mas, como concurseiro bom \u00e9 concurseiro preparado, vamos l\u00e1 desvendar este mist\u00e9rio para n\u00e3o ser pego de surpresa na prova.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Afinal, o que \u00e9 passividade?<\/strong><\/h2>\n\n\n\n<p>De acordo com a Moderna Gram\u00e1tica Portuguesa, de<a href=\"https:\/\/www.academia.org.br\/academicos\/evanildo-bechara\/biografia\" target=\"_blank\" rel=\"noreferrer noopener\"> Evanildo Bechara<\/a>, <strong>voz passiva e passividade <\/strong>s\u00e3o conceitos diferentes entre si.<\/p>\n\n\n\n<p>Segundo ele, <strong>VOZ<\/strong> \u00e9 a <strong>forma<\/strong> especial <strong>pela qual o verbo se apresenta <\/strong>com a finalidade de<strong> indicar que a pessoa recebe a a\u00e7\u00e3o<\/strong>, enquanto que a <strong>PASSIVIDADE<\/strong> \u00e9 o <strong>fato do sujeito receber a a\u00e7\u00e3o <\/strong>verbal.<\/p>\n\n\n\n<p>Veja <strong>alguns exemplos<\/strong> de passividade:<\/p>\n\n\n\n<p>(1) A sociedade <strong>sofre <\/strong>com a pandemia.<\/p>\n\n\n\n<p>(2) Os criminosos<strong> recebem <\/strong>o merecido castigo.<\/p>\n\n\n\n<p>(3) Os garotos <strong>levaram <\/strong>uma surra.<\/p>\n\n\n\n<p>Nestes casos, note que as estruturas oracionais n\u00e3o seguem a constru\u00e7\u00e3o constante na voz passiva anal\u00edtica, embora o verbo tenha sentido passivo (&#8220;sofre&#8221;, &#8220;recebem&#8221; e &#8220;levaram&#8221;). Desta forma, atrav\u00e9s das frases acima, percebe-se que<strong> h\u00e1 a passividade<\/strong> (fato do sujeito receber a a\u00e7\u00e3o verbal), <strong>ainda que a frase n\u00e3o esteja na voz passiva<\/strong>.<\/p>\n\n\n\n<p>Isto \u00e9, <strong>a passividade traduz-se<\/strong> n\u00e3o s\u00f3 pela voz passiva, mas <strong>tamb\u00e9m pela ativa, se o verbo tiver sentido passivo<\/strong>. <\/p>\n\n\n\n<p>Ora, nas tr\u00eas constru\u00e7\u00f5es, n\u00e3o h\u00e1 estrutura de voz passiva, mas os sujeitos (<em>\u201cA sociedade&#8221;, \u201cOs criminosos&#8221; e &#8220;Os garotos&#8221;<\/em>) s\u00e3o passivos em rela\u00e7\u00e3o \u00e0 a\u00e7\u00e3o verbal. <\/p>\n\n\n\n<p>Deste modo, \u00e9 correto afirmar que h\u00e1 passividade nas frases acima, mesmo n\u00e3o ocorrendo voz passiva.<\/p>\n\n\n\n<p><strong><span class=\"has-inline-color has-vivid-red-color\">TOME NOTA:<\/span><\/strong> Para Bechara, a passividade <strong>NEM SEMPRE<\/strong> corresponde \u00e0 voz passiva. Ou seja, &#8220;<em>mesmo que a estrutura sint\u00e1tica da frase seja classificada como voz ativa, a an\u00e1lise sem\u00e2ntica mostra que o sujeito recebe a a\u00e7\u00e3o, ocorrendo, portanto a passividade (o sujeito sofre a a\u00e7\u00e3o) numa frase em que a gram\u00e1tica tradicional classificaria como voz ativa<\/em>&#8220;.<br \/><\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Resumo da \u00d3pera<\/strong><\/h2>\n\n\n\n<p>A <strong>PASSIVIDADE <\/strong>diz respeito ao fato de <strong>um elemento sofrer uma a\u00e7\u00e3o<\/strong>, podendo se apresentar, inclusive, em estruturas que <strong>N\u00c3O ESTEJAM<\/strong> na voz passiva. <\/p>\n\n\n\n<p>Pegando novamente a frase:&#8221; Os criminosos<strong> recebem <\/strong>o merecido castigo&#8221; como exemplo, verificamos que, embora o verbo &#8220;receber&#8221; esteja na voz ativa, h\u00e1 passividade na frase, pois os criminosos receberam o castigo, ou seja, sofreram a a\u00e7\u00e3o.<\/p>\n\n\n\n<p>Em outras palavras, embora a voz passiva possa ser considerada um meio de express\u00e3o lingu\u00edstica da passividade, esta n\u00e3o deve ser entendida como sin\u00f4nimo dela, pois a <strong>passividade \u00e9 uma caracter\u00edstica sem\u00e2ntica<\/strong>. Ocorre quando o sujeito recebe ou sofre a a\u00e7\u00e3o verbal.<\/p>\n\n\n\n<p>Desta forma, as <strong>ora\u00e7\u00f5es na voz passiva possuem a passividade, mas a passividade n\u00e3o se encontra exclusivamente em ora\u00e7\u00f5es na voz passiva.<\/strong><\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Conclus\u00e3o<\/strong><\/h2>\n\n\n\n<p>E a\u00ed? Gostaram? Esperamos que, com esta resumida an\u00e1lise sobre o assunto, os concurseiros de plant\u00e3o passem a entender estes conceitos com mais clareza e aprendam, de uma vez por todas, as principais diferen\u00e7as entre eles.<\/p>\n\n\n\n<p>Contudo, sempre \u00e9 bom ressaltar que este artigo tem a finalidade de ser apenas uma breve s\u00edntese sobre o assunto e n\u00e3o tem a pretens\u00e3o de esgot\u00e1-lo e nem de suprir todo o conte\u00fado, mas sim de complement\u00e1-lo.<\/p>\n\n\n\n<p>Para que voc\u00eas dominem a banca organizadora e se classifiquem no concurso almejado \u00e9 de sum\u00edssima import\u00e2ncia que estudem pelas aulas em PDF dos <a href=\"https:\/\/www.estrategiaconcursos.com.br\/assinaturas-2022\/\" target=\"_blank\" rel=\"noreferrer noopener\">Cursos do Estrat\u00e9gia<\/a>, pois o material constante nas aulas \u00e9 completo e formulado por professores de alto n\u00edvel e plenamente gabaritados.<\/p>\n\n\n\n<p>Conhe\u00e7am tamb\u00e9m o <a href=\"https:\/\/www.estrategiaconcursos.com.br\/cursosPorConcurso\/sistema-de-questoes\/\" target=\"_blank\" rel=\"noreferrer noopener\">Sistema de Quest\u00f5es do Estrat\u00e9gia<\/a>. Afinal, a \u00fanica maneira de consolidar o conte\u00fado de maneira satisfat\u00f3ria e descobrir de que forma os examinadores pensam \u00e9 atrav\u00e9s da resolu\u00e7\u00e3o de quest\u00f5es.<\/p>\n\n\n\n<p>Um excelente estudo a todos e at\u00e9 a pr\u00f3xima!<\/p>\n\n\n\n<p>Renata Sodr\u00e9<\/p>\n\n\n\n<h2 class=\"has-text-align-center wp-block-heading\" id=\"h-cursos-e-assinaturas\">Cursos e Assinaturas <\/h2>\n\n\n\n<p>Prepare-se com o melhor material e com quem mais aprova em Concursos P\u00fablicos em todo o pa\u00eds!<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p class=\"has-text-align-center has-white-color has-vivid-purple-background-color has-text-color has-background\"><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-abertos\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Concursos abertos<\/strong><\/a><\/p>\n\n\n\n<p class=\"has-text-align-center has-white-color has-vivid-purple-background-color has-text-color has-background\"><strong><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-2022\/\" target=\"_blank\" rel=\"noreferrer noopener\">Concursos 2022<\/a><\/strong><\/p>\n\n\n\n<div class=\"container\" id=\"boxes\">\n  <div class=\"row\">\n    <div class=\"col-sm\">\n      <div class=\"estrategia\" id=\"box-assinatura\">\n        <h3 class=\"titulo-assinatura\">Assinatura de Concursos<\/h3>\n        <p class=\"subtitulo-assinatura\">Assinatura de 1 ano ou 2 anos<\/p>\n        <div class=\"box-botao\">\n          <a class=\"btn-assinatura\" target=\"_blank\" href=\"https:\/\/www.estrategiaconcursos.com.br\/assinaturas\/\" role=\"button\" rel=\"noopener noreferrer\">ASSINE AGORA<\/a>\n        <\/div>\n      <\/div>\n      \n    <\/div><\/div><\/div>\n\n\n\n<h2 class=\"has-text-align-center wp-block-heading\" id=\"h-\"><\/h2>\n","protected":false},"excerpt":{"rendered":"<p>Ol\u00e1, concurseiros, tudo bem? Sabemos que a L\u00edngua Portuguesa \u00e9 uma disciplina-chave em todos os concursos. Quem a domina, certamente sai com grande vantagem na frente dos outros candidatos. Um dos assuntos que gera grande d\u00favida nos alunos \u00e9 sobre voz passiva e passividade. Voc\u00ea sabe o que s\u00e3o? Sabe a diferen\u00e7a entre elas? Com [&hellip;]<\/p>\n","protected":false},"author":2310,"featured_media":943936,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"post_tipo":"article","footnotes":""},"categories":[1],"tags":[366,15,2368,220296,220295],"tax_estado":[219964,219965,219966,219967,219968,219969,219963,219970,219971,219972,219973,219974,219975,219976,219977,219978,219979,219980,219981,219982,219983,219984,219985,219986,219987,219988,219989,219990],"class_list":["post-943932","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cursos-e-concursos","tag-lingua-portuguesa","tag-portugues","tag-portugues-para-concursos","tag-voz-passiva-e-passividade","tag-vozes-verbais","tax_estado-ac","tax_estado-al","tax_estado-am","tax_estado-ap","tax_estado-ba","tax_estado-ce","tax_estado-concursos-federais","tax_estado-df","tax_estado-es","tax_estado-go","tax_estado-ma","tax_estado-mg","tax_estado-ms","tax_estado-mt","tax_estado-pa","tax_estado-pb","tax_estado-pe","tax_estado-pi","tax_estado-pr","tax_estado-rj","tax_estado-rn","tax_estado-ro","tax_estado-rr","tax_estado-rs","tax_estado-sc","tax_estado-se","tax_estado-sp","tax_estado-to"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.2 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Voz Passiva e Passividade<\/title>\n<meta name=\"description\" content=\"Aprenda de uma vez a diferen\u00e7a entre voz passiva e passividade e gabarite as provas dos concursos p\u00fablicos.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/voz-passiva-e-passividade\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Voz Passiva e Passividade\" \/>\n<meta property=\"og:description\" content=\"Aprenda de uma vez a diferen\u00e7a entre voz passiva e passividade e gabarite as provas dos concursos p\u00fablicos.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/voz-passiva-e-passividade\/\" \/>\n<meta property=\"og:site_name\" content=\"Estrat\u00e9gia Concursos\" \/>\n<meta property=\"article:published_time\" content=\"2022-01-17T11:21:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/01\/10221915\/portrait-pensive-young-girl-making-notes-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Renata Ara\u00fajo Sodr\u00e9 da Silva\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:site\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Renata Ara\u00fajo Sodr\u00e9 da Silva\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"9 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/voz-passiva-e-passividade\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/voz-passiva-e-passividade\/\"},\"author\":{\"name\":\"Renata Ara\u00fajo Sodr\u00e9 da Silva\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/a929d42d707cf35b05df2e2219927433\"},\"headline\":\"Voz Passiva e Passividade\",\"datePublished\":\"2022-01-17T11:21:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/voz-passiva-e-passividade\/\"},\"wordCount\":1677,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/voz-passiva-e-passividade\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/01\/10221915\/portrait-pensive-young-girl-making-notes-scaled.jpg\",\"keywords\":[\"L\u00edngua Portuguesa\",\"Portugu\u00eas\",\"PORTUGU\u00caS PARA CONCURSOS\",\"Voz Passiva e Passividade\",\"Vozes Verbais\"],\"articleSection\":[\"Concursos P\u00fablicos\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/voz-passiva-e-passividade\/#respond\"]}],\"copyrightYear\":\"2022\",\"copyrightHolder\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/voz-passiva-e-passividade\/\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/voz-passiva-e-passividade\/\",\"name\":\"Voz Passiva e Passividade\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/voz-passiva-e-passividade\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/voz-passiva-e-passividade\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/01\/10221915\/portrait-pensive-young-girl-making-notes-scaled.jpg\",\"datePublished\":\"2022-01-17T11:21:00+00:00\",\"description\":\"Aprenda de uma vez a diferen\u00e7a entre voz passiva e passividade e gabarite as provas dos concursos p\u00fablicos.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/voz-passiva-e-passividade\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/voz-passiva-e-passividade\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/voz-passiva-e-passividade\/#primaryimage\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/01\/10221915\/portrait-pensive-young-girl-making-notes-scaled.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/01\/10221915\/portrait-pensive-young-girl-making-notes-scaled.jpg\",\"width\":2560,\"height\":1707,\"caption\":\"Portrait of a pensive young girl making notes while sitting with books isolated over yellow background\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/voz-passiva-e-passividade\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Voz Passiva e Passividade\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"name\":\"Estrat\u00e9gia Concursos\",\"description\":\"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.\",\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\",\"name\":\"Estrat\u00e9gia Concursos\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"width\":230,\"height\":60,\"caption\":\"Estrat\u00e9gia Concursos\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/EstratConcursos\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/a929d42d707cf35b05df2e2219927433\",\"name\":\"Renata Ara\u00fajo Sodr\u00e9 da Silva\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/ca9182e3bf6658feab2bdbe93f36f56f9771baa281700b03ec5836dcf5c88918?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/ca9182e3bf6658feab2bdbe93f36f56f9771baa281700b03ec5836dcf5c88918?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/ca9182e3bf6658feab2bdbe93f36f56f9771baa281700b03ec5836dcf5c88918?s=96&d=mm&r=g\",\"caption\":\"Renata Ara\u00fajo Sodr\u00e9 da Silva\"},\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/renata-araujosodregmail-com\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Voz Passiva e Passividade","description":"Aprenda de uma vez a diferen\u00e7a entre voz passiva e passividade e gabarite as provas dos concursos p\u00fablicos.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.estrategiaconcursos.com.br\/blog\/voz-passiva-e-passividade\/","og_locale":"pt_BR","og_type":"article","og_title":"Voz Passiva e Passividade","og_description":"Aprenda de uma vez a diferen\u00e7a entre voz passiva e passividade e gabarite as provas dos concursos p\u00fablicos.","og_url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/voz-passiva-e-passividade\/","og_site_name":"Estrat\u00e9gia Concursos","article_published_time":"2022-01-17T11:21:00+00:00","og_image":[{"width":2560,"height":1707,"url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/01\/10221915\/portrait-pensive-young-girl-making-notes-scaled.jpg","type":"image\/jpeg"}],"author":"Renata Ara\u00fajo Sodr\u00e9 da Silva","twitter_card":"summary_large_image","twitter_creator":"@EstratConcursos","twitter_site":"@EstratConcursos","twitter_misc":{"Escrito por":"Renata Ara\u00fajo Sodr\u00e9 da Silva","Est. tempo de leitura":"9 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/voz-passiva-e-passividade\/#article","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/voz-passiva-e-passividade\/"},"author":{"name":"Renata Ara\u00fajo Sodr\u00e9 da Silva","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/a929d42d707cf35b05df2e2219927433"},"headline":"Voz Passiva e Passividade","datePublished":"2022-01-17T11:21:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/voz-passiva-e-passividade\/"},"wordCount":1677,"commentCount":0,"publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/voz-passiva-e-passividade\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/01\/10221915\/portrait-pensive-young-girl-making-notes-scaled.jpg","keywords":["L\u00edngua Portuguesa","Portugu\u00eas","PORTUGU\u00caS PARA CONCURSOS","Voz Passiva e Passividade","Vozes Verbais"],"articleSection":["Concursos P\u00fablicos"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/voz-passiva-e-passividade\/#respond"]}],"copyrightYear":"2022","copyrightHolder":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/voz-passiva-e-passividade\/","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/voz-passiva-e-passividade\/","name":"Voz Passiva e Passividade","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/voz-passiva-e-passividade\/#primaryimage"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/voz-passiva-e-passividade\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/01\/10221915\/portrait-pensive-young-girl-making-notes-scaled.jpg","datePublished":"2022-01-17T11:21:00+00:00","description":"Aprenda de uma vez a diferen\u00e7a entre voz passiva e passividade e gabarite as provas dos concursos p\u00fablicos.","breadcrumb":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/voz-passiva-e-passividade\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/voz-passiva-e-passividade\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/voz-passiva-e-passividade\/#primaryimage","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/01\/10221915\/portrait-pensive-young-girl-making-notes-scaled.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/01\/10221915\/portrait-pensive-young-girl-making-notes-scaled.jpg","width":2560,"height":1707,"caption":"Portrait of a pensive young girl making notes while sitting with books isolated over yellow background"},{"@type":"BreadcrumbList","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/voz-passiva-e-passividade\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.estrategiaconcursos.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Voz Passiva e Passividade"}]},{"@type":"WebSite","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","name":"Estrat\u00e9gia Concursos","description":"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.","publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization","name":"Estrat\u00e9gia Concursos","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","width":230,"height":60,"caption":"Estrat\u00e9gia Concursos"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/EstratConcursos"]},{"@type":"Person","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/a929d42d707cf35b05df2e2219927433","name":"Renata Ara\u00fajo Sodr\u00e9 da Silva","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/ca9182e3bf6658feab2bdbe93f36f56f9771baa281700b03ec5836dcf5c88918?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ca9182e3bf6658feab2bdbe93f36f56f9771baa281700b03ec5836dcf5c88918?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ca9182e3bf6658feab2bdbe93f36f56f9771baa281700b03ec5836dcf5c88918?s=96&d=mm&r=g","caption":"Renata Ara\u00fajo Sodr\u00e9 da Silva"},"url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/renata-araujosodregmail-com\/"}]}},"_links":{"self":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/943932","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/users\/2310"}],"replies":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/comments?post=943932"}],"version-history":[{"count":23,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/943932\/revisions"}],"predecessor-version":[{"id":1125825,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/943932\/revisions\/1125825"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media\/943936"}],"wp:attachment":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media?parent=943932"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/categories?post=943932"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tags?post=943932"},{"taxonomy":"tax_estado","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tax_estado?post=943932"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}