{"id":907972,"date":"2021-11-22T08:24:00","date_gmt":"2021-11-22T11:24:00","guid":{"rendered":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?p=907972"},"modified":"2021-11-24T20:24:11","modified_gmt":"2021-11-24T23:24:11","slug":"analise-estatistica-do-tce-sc","status":"publish","type":"post","link":"https:\/\/www.estrategiaconcursos.com.br\/blog\/analise-estatistica-do-tce-sc\/","title":{"rendered":"An\u00e1lise estat\u00edstica do TCE SC: para voc\u00ea ser aprovado"},"content":{"rendered":"\n<p> Ol\u00e1, tudo bem com voc\u00ea? No artigo de hoje vamos fazer uma an\u00e1lise estat\u00edstica do novo concurso do TCE SC: para voc\u00ea ser aprovado. Vamos l\u00e1? <\/p>\n\n\n\n<figure class=\"wp-block-image is-resized is-style-default\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2019\/08\/23123024\/tce-sc-foto.jpg\" alt=\"An\u00e1lise estat\u00edstica do TCE SC: para voc\u00ea ser aprovado\" class=\"wp-image-412548\" width=\"839\" height=\"436\" srcset=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2019\/08\/23123024\/tce-sc-foto.jpg 770w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2019\/08\/23123024\/tce-sc-foto.jpg 300w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2019\/08\/23123024\/tce-sc-foto.jpg 768w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2019\/08\/23123024\/tce-sc-foto.jpg 610w\" sizes=\"auto, (max-width: 839px) 100vw, 839px\" \/><figcaption>An\u00e1lise estat\u00edstica do TCE SC: para voc\u00ea ser aprovado<\/figcaption><\/figure>\n\n\n\n<p>Foi&nbsp;<strong>publicado o edital<\/strong>&nbsp;para o novo concurso do Tribunal de Contas de Santa Catarina (TCE-SC)!<\/p>\n\n\n\n<p>S\u00e3o <strong>40 vagas imediatas mais 120 para forma\u00e7\u00e3o de cadastro reserva<\/strong> para o cargo de Auditor de Controle Externo. Est\u00e1 preparado para ser aprovado neste concurso?<\/p>\n\n\n\n<p>Lembrando que as vagas s\u00e3o nas \u00e1reas de Administra\u00e7\u00e3o, Ci\u00eancias da Computa\u00e7\u00e3o, Ci\u00eancias Cont\u00e1beis, Direito, Ci\u00eancias Econ\u00f4micas e Engenharia Civil.<\/p>\n\n\n\n<p>E a Banca?<\/p>\n\n\n\n<p>A Banca queridinha para a \u00e1rea de Controle: o Cebraspe.<\/p>\n\n\n\n<p>Depois do Tribunal de Contas da Uni\u00e3o e da Controladoria Geral da Uni\u00e3o escolher a FGV como banca para o novo concurso, a banca examinadora queridinha para a \u00e1rea de controle voltou.<\/p>\n\n\n\n<p>A prova est\u00e1 prevista para 06\/03\/2022. Se voc\u00ea est\u00e1 come\u00e7ando a estudar no 30\/11\/2022, s\u00e3o 96 dias at\u00e9 a prova. Se voc\u00ea estuda 4 horas por dia at\u00e9 a prova, voc\u00ea ter\u00e1 estudado um total de 384 horas.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-an-lise-estat-stica-do-tce-sc-conhecimentos-b-sicos-para-todos-os-cargos\">An\u00e1lise estat\u00edstica do TCE SC: Conhecimentos B\u00e1sicos para todos os cargos<\/h2>\n\n\n\n<p>As provas objetivas de conhecimentos b\u00e1sicos para todos os cargos totalizam 40 quest\u00f5es. Abaixo est\u00e3o os assuntos exigidos para essa prova:<\/p>\n\n\n\n<figure class=\"wp-block-table is-style-stripes\"><table><tbody><tr><td>Conhecimentos B\u00e1sicos<\/td><\/tr><tr><td>Portugu\u00eas<\/td><\/tr><tr><td>Auditoria Governamental, Compliance, Gest\u00e3o de Risco e Governan\u00e7a<\/td><\/tr><tr><td>Controle Externo da Administra\u00e7\u00e3o P\u00fablica<\/td><\/tr><tr><td>No\u00e7\u00f5es de Direito Administrativo (exceto para \u00c1rea: Direito)<\/td><\/tr><tr><td>No\u00e7\u00f5es de Direito Constitucional (exceto para \u00c1rea: Direito)<\/td><\/tr><tr><td>Direito Financeiro<\/td><\/tr><tr><td>\u00c9tica no Servi\u00e7o P\u00fablico<\/td><\/tr><tr><td>Conhecimentos sobre Santa Catarina<\/td><\/tr><\/tbody><\/table><figcaption>Mat\u00e9rias Conhecimentos B\u00e1sicos TCE SC<\/figcaption><\/figure>\n\n\n\n<p>Com base na an\u00e1lise dos concursos anteriores para os cargos de Auditor de Controle Externo realizados pelo Cebraspe, tem-se a seguinte import\u00e2ncia quanto as mat\u00e9rias exigidas como Conhecimentos B\u00e1sicos:<\/p>\n\n\n\n<figure class=\"wp-block-table is-style-stripes\"><table><tbody><tr><td>Conhecimentos B\u00e1sicos<\/td><td><\/td><\/tr><tr><td>Portugu\u00eas<\/td><td>29%<\/td><\/tr><tr><td>Auditoria Governamental, Compliance, Gest\u00e3o de Risco e Governan\u00e7a<\/td><td>14%<\/td><\/tr><tr><td>Controle Externo da Administra\u00e7\u00e3o P\u00fablica<\/td><td>14%<\/td><\/tr><tr><td>No\u00e7\u00f5es de Direito Administrativo (exceto para \u00c1rea: Direito)<\/td><td>19%<\/td><\/tr><tr><td>No\u00e7\u00f5es de Direito Constitucional (exceto para \u00c1rea: Direito)<\/td><td>10%<\/td><\/tr><tr><td>Direito Financeiro<\/td><td>10%<\/td><\/tr><tr><td>\u00c9tica no Servi\u00e7o P\u00fablico<\/td><td>2%<\/td><\/tr><tr><td>Conhecimentos sobre Santa Catarina<\/td><td>2%<\/td><\/tr><tr><td>total<\/td><td>100%<\/td><\/tr><\/tbody><\/table><figcaption>Import\u00e2ncia nos concursos anteriores para o cargo de Auditor de Controle Externo realizados pelo Cebraspe<\/figcaption><\/figure>\n\n\n\n<p>Assim, vemos a import\u00e2ncia de Portugu\u00eas nos concursos anteriores para o cargo de Auditor de Controle Externo realizados pelo Cebraspe. Apenas essa mat\u00e9ria totalizou quase 29% dos assuntos exigidos em Conhecimentos B\u00e1sicos nos concursos anteriores para o cargo de Auditor realizados por essa Banca Examinadora.<\/p>\n\n\n\n<p>Em segundo lugar de disciplina mais exigida ficou Direito Administrativo com quase 20% dos assuntos exigidos em Conhecimentos B\u00e1sicos nos concursos anteriores.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">An\u00e1lise estat\u00edstica do TCE SC: Conhecimentos B\u00e1sicos para todos os cargo<\/h2>\n\n\n\n<p>Quantidade de PDFs para esse concurso por mat\u00e9ria:<\/p>\n\n\n\n<figure class=\"wp-block-table is-style-stripes\"><table><tbody><tr><td>Conhecimentos B\u00e1sicos<\/td><td>Quantidade de PDF&nbsp;<\/td><\/tr><tr><td>Portugu\u00eas<\/td><td>11<\/td><\/tr><tr><td>Auditoria Governamental, Compliance, Gest\u00e3o de Risco e Governan\u00e7a<\/td><td>13<\/td><\/tr><tr><td>Controle Externo da Administra\u00e7\u00e3o P\u00fablica<\/td><td>7<\/td><\/tr><tr><td>No\u00e7\u00f5es de Direito Administrativo (exceto para \u00c1rea: Direito)<\/td><td>23<\/td><\/tr><tr><td>No\u00e7\u00f5es de Direito Constitucional (exceto para \u00c1rea: Direito)<\/td><td>14<\/td><\/tr><tr><td>Direito Financeiro<\/td><td>16<\/td><\/tr><tr><td>\u00c9tica no Servi\u00e7o P\u00fablico<\/td><td>3<\/td><\/tr><tr><td>Conhecimentos sobre Santa Catarina<\/td><td>5<\/td><\/tr><tr><td>total<\/td><td>92<\/td><\/tr><\/tbody><\/table><figcaption>Quantidade de PDF por mat\u00e9ria<\/figcaption><\/figure>\n\n\n\n<p>Assim, a parte de Conhecimentos b\u00e1sicos totaliza 92 PDFs com assuntos. Sendo \u00c9tica no Servi\u00e7o P\u00fablico a mat\u00e9ria com menos PDFs (3) e No\u00e7\u00f5es de Direito Administrativo (exceto para \u00c1rea: Direito) a mat\u00e9ria com mais PDFs (23).<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">An\u00e1lise estat\u00edstica do TCE SC: Conhecimentos B\u00e1sicos para todos os cargos<\/h2>\n\n\n\n<p>Os assuntos mais exigidos nas provas anteriores de Conhecimento B\u00e1sico foram:<\/p>\n\n\n\n<figure class=\"wp-block-table is-style-stripes\"><table><tbody><tr><td>Assuntos mais exigidos<\/td><\/tr><tr><td>Interpreta\u00e7\u00e3o de Textos<\/td><\/tr><tr><td>No\u00e7\u00f5es Gerais de Compreens\u00e3o e Interpreta\u00e7\u00e3o de Texto<\/td><\/tr><tr><td>Controle da administra\u00e7\u00e3o p\u00fablica<\/td><\/tr><tr><td>Sintaxe<\/td><\/tr><tr><td>Lei Org\u00e2nica<\/td><\/tr><\/tbody><\/table><figcaption>Assuntos mais exigidos<\/figcaption><\/figure>\n\n\n\n<p>Sendo assim, percebemos mais uma vez a import\u00e2ncia de Portugu\u00eas, dado que dos 5 assuntos mais exigidos, tr\u00eas deles fazem parte dessa disciplina. S\u00e3o eles: Interpreta\u00e7\u00e3o de texto, No\u00e7\u00f5es Gerais de Compreens\u00e3o e Interpreta\u00e7\u00e3o de Texto e Sintaxe.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">An\u00e1lise estat\u00edstica do TCE SC: Conhecimentos Espec\u00edficos para a \u00e1rea de Administra\u00e7\u00e3o <\/h2>\n\n\n\n<p>As provas objetivas de conhecimentos espec\u00edficos para a \u00e1rea de Administra\u00e7\u00e3o ser\u00e3o compostas de 60 quest\u00f5es. Abaixo est\u00e3o os assuntos exigidos para essa prova: <\/p>\n\n\n\n<figure class=\"wp-block-table is-style-stripes\"><table><tbody><tr><td>Conhecimentos Espec\u00edficos \u2013 Administra\u00e7\u00e3o<\/td><\/tr><tr><td>Administra\u00e7\u00e3o Geral<\/td><\/tr><tr><td>Administra\u00e7\u00e3o P\u00fablica<\/td><\/tr><tr><td>Administra\u00e7\u00e3o Or\u00e7ament\u00e1ria e Financeira e Or\u00e7amento P\u00fablico<\/td><\/tr><\/tbody><\/table><figcaption>Disciplinas Exigidas na prova do TCE SC &#8211; Administra\u00e7\u00e3o<\/figcaption><\/figure>\n\n\n\n<p>Assim, essas 3 mat\u00e9rias totalizam 60% da sua prova objetiva caso voc\u00ea queira prestar o concurso do TCE SC para a \u00e1rea de Administra\u00e7\u00e3o. <\/p>\n\n\n\n<p>Vamos ver agora a quantidade de PDFs por cada mat\u00e9ria:<\/p>\n\n\n\n<figure class=\"wp-block-table is-style-stripes\"><table><tbody><tr><td>Conhecimentos Espec\u00edficos \u2013 Administra\u00e7\u00e3o<\/td><td>Quantidade de PDF<\/td><\/tr><tr><td>Administra\u00e7\u00e3o Geral<\/td><td>17<\/td><\/tr><tr><td>Administra\u00e7\u00e3o P\u00fablica<\/td><td>17<\/td><\/tr><tr><td>Administra\u00e7\u00e3o Or\u00e7ament\u00e1ria e Financeira e Or\u00e7amento P\u00fablico<\/td><td>16<\/td><\/tr><tr><td>total<\/td><td>50<\/td><\/tr><\/tbody><\/table><figcaption>Quantidade de PDF<\/figcaption><\/figure>\n\n\n\n<p>Como s\u00e3o 92 PDFs na parte de Conhecimentos B\u00e1sicos adicionados de 50 PDFs na parte de Conhecimentos espec\u00edficos para a \u00e1rea de administra\u00e7\u00e3o, o total s\u00e3o 142. Considerando que desses 142 PDFs, apenas 50 deles totalizam 60% da prova, vale muito a pena voc\u00ea focar bem nessas espec\u00edficas.<\/p>\n\n\n\n<p>Lembrando que Portugu\u00eas tamb\u00e9m tem uma import\u00e2ncia consider\u00e1vel para o Cebraspe (isso para todos os cargos).<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">An\u00e1lise estat\u00edstica do TCE SC: Conhecimentos Espec\u00edficos para a \u00e1rea de Ci\u00eancias Cont\u00e1beis  <\/h2>\n\n\n\n<p> As provas objetivas de conhecimentos espec\u00edficos para a \u00e1rea de Ci\u00eancias Cont\u00e1beis ser\u00e3o compostas de 60 quest\u00f5es. Abaixo est\u00e3o os assuntos exigidos para essa prova:  <\/p>\n\n\n\n<figure class=\"wp-block-table is-style-stripes\"><table><tbody><tr><td>Conhecimentos Espec\u00edficos \u2013 Ci\u00eancias Cont\u00e1beis<\/td><\/tr><tr><td>Contabilidade Geral<\/td><\/tr><tr><td>Contabilidade P\u00fablica<\/td><\/tr><tr><td>Licita\u00e7\u00f5es, Contratos e Conv\u00eanios<\/td><\/tr><\/tbody><\/table><figcaption>Exig\u00eancias para a prova de Conhecimentos espec\u00edficos &#8211; \u00e1rea de ci\u00eancias cont\u00e1beis<\/figcaption><\/figure>\n\n\n\n<p>Desse modo, essas 3 mat\u00e9rias totalizam 60% da sua prova objetiva caso voc\u00ea queira prestar o concurso do TCE SC para a \u00e1rea de Ci\u00eancias Cont\u00e1beis. <\/p>\n\n\n\n<p>Vamos ver agora a quantidade de PDFs por cada mat\u00e9ria:<\/p>\n\n\n\n<figure class=\"wp-block-table is-style-stripes\"><table><tbody><tr><td>Conhecimentos Espec\u00edficos \u2013 Ci\u00eancias Cont\u00e1beis<\/td><td>Quantidade de PDF<\/td><\/tr><tr><td>Contabilidade Geral<\/td><td>34<\/td><\/tr><tr><td>Contabilidade P\u00fablica<\/td><td>22<\/td><\/tr><tr><td>Licita\u00e7\u00f5es, Contratos e Conv\u00eanios<\/td><td>9<\/td><\/tr><tr><td>total<\/td><td>65<\/td><\/tr><\/tbody><\/table><figcaption>Quantidade de PDF por mat\u00e9ria para a \u00e1rea de ci\u00eancias cont\u00e1beis<\/figcaption><\/figure>\n\n\n\n<p>Como s\u00e3o 92 PDFs na parte de Conhecimentos B\u00e1sicos adicionados de 65 PDFs na parte de Conhecimentos espec\u00edficos para a \u00e1rea de ci\u00eancias cont\u00e1beis, o total s\u00e3o 157. Considerando que desses 157 PDFs, apenas 65 deles totalizam 60% da prova, isto \u00e9, menos da metade, vale muito a pena voc\u00ea focar bem nessas espec\u00edficas.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">An\u00e1lise estat\u00edstica do TCE SC: Conhecimentos Espec\u00edficos para a \u00e1rea de <strong>Ci\u00eancias Econ\u00f4micas<\/strong>  <\/h2>\n\n\n\n<p>As provas objetivas de conhecimentos espec\u00edficos para a \u00e1rea de Ci\u00eancias Econ\u00f4micas ser\u00e3o compostas de 60 quest\u00f5es. Abaixo est\u00e3o os assuntos exigidos para essa prova:   <\/p>\n\n\n\n<figure class=\"wp-block-table is-style-stripes\"><table><tbody><tr><td>Conhecimentos Espec\u00edficos \u2013 Ci\u00eancias Econ\u00f4micas<\/td><\/tr><tr><td>Macroeconomia<\/td><\/tr><tr><td>Microeconomia<\/td><\/tr><tr><td>Economia do Setor P\u00fablico<\/td><\/tr><tr><td>Matem\u00e1tica Financeira<\/td><\/tr><tr><td>Estat\u00edstica<\/td><\/tr><tr><td>Econometria<\/td><\/tr><\/tbody><\/table><figcaption>Conhecimentos Espec\u00edficos para a \u00e1rea de Ci\u00eancias Econ\u00f4micas<\/figcaption><\/figure>\n\n\n\n<p>Assim, as mat\u00e9rias listadas acima totalizam 60% da sua prova objetiva caso voc\u00ea queira prestar o concurso do TCE SC para a \u00e1rea de Ci\u00eancias Econ\u00f4micas. <\/p>\n\n\n\n<p>Vamos ver agora a quantidade de PDFs por cada mat\u00e9ria:<\/p>\n\n\n\n<figure class=\"wp-block-table is-style-stripes\"><table><tbody><tr><td>Conhecimentos Espec\u00edficos \u2013 Ci\u00eancias Econ\u00f4micas<\/td><td>Quantidade de PDFs<\/td><\/tr><tr><td>Macroeconomia<\/td><td>8<\/td><\/tr><tr><td>Microeconomia<\/td><td>9<\/td><\/tr><tr><td>Economia do Setor P\u00fablico<\/td><td>3<\/td><\/tr><tr><td>Matem\u00e1tica Financeira<\/td><td>7<\/td><\/tr><tr><td>Estat\u00edstica<\/td><td>17<\/td><\/tr><tr><td>total<\/td><td>44<\/td><\/tr><\/tbody><\/table><figcaption>Quantidade de PDF por mat\u00e9ria<\/figcaption><\/figure>\n\n\n\n<p>Como s\u00e3o 92 PDFs na parte de Conhecimentos B\u00e1sicos adicionados de 44 PDFs na parte de Conhecimentos espec\u00edficos para a \u00e1rea de ci\u00eancias econ\u00f4micas, o total s\u00e3o 136. Assim, menos de 1\/3 da quantidade de PDFs representa 60% dos assuntos exigidos para o cargo.<\/p>\n\n\n\n<p>Preciso falar o custo x benef\u00edcios dessas mat\u00e9rias?<\/p>\n\n\n\n<p>Muito alto!!<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">An\u00e1lise estat\u00edstica do TCE SC: Conhecimentos Espec\u00edficos para a \u00e1rea de <strong>Direito<\/strong>   <\/h2>\n\n\n\n<p> As provas objetivas de conhecimentos espec\u00edficos para a \u00e1rea de Direito ser\u00e3o compostas de 60 quest\u00f5es. Abaixo est\u00e3o os assuntos exigidos para essa prova:    <\/p>\n\n\n\n<figure class=\"wp-block-table is-style-stripes\"><table><tbody><tr><td>Conhecimentos Espec\u00edficos \u2013 Direito<\/td><\/tr><tr><td>Direito Administrativo<\/td><\/tr><tr><td>Direito Constitucional<\/td><\/tr><tr><td>Direito Civil<\/td><\/tr><tr><td>Direito Processual Civil<\/td><\/tr><tr><td>Direito Tribut\u00e1rio<\/td><\/tr><tr><td>Direito Penal<\/td><\/tr><tr><td>Direito Processual Penal<\/td><\/tr><\/tbody><\/table><figcaption>Mat\u00e9rias Exigidas para a \u00e1rea de Direito<\/figcaption><\/figure>\n\n\n\n<p>Assim, as mat\u00e9rias listadas acima totalizam 60% da sua prova objetiva caso voc\u00ea queira prestar o concurso do TCE SC para a \u00e1rea de Direito. <\/p>\n\n\n\n<p>Vamos ver agora a quantidade de PDFs por cada mat\u00e9ria:<\/p>\n\n\n\n<figure class=\"wp-block-table is-style-stripes\"><table><tbody><tr><td>Conhecimentos Espec\u00edficos \u2013 Direito<\/td><td>Quantidade de PDFs<\/td><\/tr><tr><td>Direito Administrativo<\/td><td>23<\/td><\/tr><tr><td>Direito Constitucional<\/td><td>14<\/td><\/tr><tr><td>Direito Civil<\/td><td>9<\/td><\/tr><tr><td>Direito Processual Civil<\/td><td>18<\/td><\/tr><tr><td>Direito Tribut\u00e1rio<\/td><td>14<\/td><\/tr><tr><td>Direito Penal<\/td><td>12<\/td><\/tr><tr><td>Direito Processual Penal<\/td><td>15<\/td><\/tr><tr><td>total<\/td><td>105<\/td><\/tr><\/tbody><\/table><figcaption>Quantidade de PDFs<\/figcaption><\/figure>\n\n\n\n<p>Assim, para o cargo do Tribunal de Contas do Estado de Santa Catarina &#8211; \u00e1rea: Direito, apesar de n\u00e3o ser exigido Direito Constitucional e Direito Administrativo na parte de Conhecimentos Gerais, essas mat\u00e9rias (assim como outras de Direito) tem uma import\u00e2ncia significativa, lembrando que a parte de conhecimentos espec\u00edficos totaliza 60% do conte\u00fado exigido na prova.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Tribunal de Contas de Santa Catarina: Como ser aprovado nesse concurso<\/h2>\n\n\n\n<p>Para ser aprovado neste concurso p\u00fablico voc\u00ea precisa fazer muitas quest\u00f5es do Cebraspe. Afinal, essa vai ser sua melhor forma de realizar revis\u00e3o, al\u00e9m disso, vai verificar como a banca examinadora cobra o assunto, o n\u00edvel de detalhamento necess\u00e1rio.<\/p>\n\n\n\n<p>Ademais, fazendo quest\u00f5es da banca voc\u00ea vai verificar quais pontos voc\u00ea precisa dar uma maior aten\u00e7\u00e3o, seja por ser muito exigido em prova, seja por voc\u00ea ter uma maior dificuldade no assunto.<\/p>\n\n\n\n<p>Fa\u00e7a simulados de concursos anteriores realizados pelo Cebraspe. Alguns exemplos de concursos anteriores para o cargo de Auditor de Controle Externo:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Tribunal de Contas de Pernambuco (2017);<\/li><li>Tribunal de Contas da Para\u00edba (2018).<\/li><\/ul>\n\n\n\n<p>Voc\u00ea vai verificar que v\u00e1rios concursos para essa \u00e1rea de Controle s\u00e3o realizados por essa banca examinadora, ent\u00e3o n\u00e3o ir\u00e3o faltar provas anteriores para voc\u00ea resolver.<\/p>\n\n\n\n<p>Simule as mesmas condi\u00e7\u00f5es do dia da prova, assim voc\u00ea ir\u00e1 verificar o que deve ser alterado para melhorar sua performance, vai monitorar o tempo gasto por quest\u00f5es, verificar alimenta\u00e7\u00e3o que precisa levar para a prova, controlar as idas ao banheiro, etc. Al\u00e9m de testar o controle do nervosismo no dia da prova.<\/p>\n\n\n\n<p>Quanto mais quest\u00f5es voc\u00ea fizer dessa banca, mais voc\u00ea vai saber o que priorizar para a prova!<\/p>\n\n\n\n<p>Espero que tenham gostado do artigo de hoje, bons estudos e uma excelente prova!<\/p>\n\n\n\n<p>Um abra\u00e7o e bons estudos!<\/p>\n\n\n\n<p>Leonardo Mathias <\/p>\n\n\n\n<p>@profleomathias<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-wp-embed is-provider-estrategia-concursos wp-block-embed-estrategia-concursos\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"wp-embedded-content\" data-secret=\"jn89WbR3Dy\"><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/ciclo-x-cronograma-de-estudo-qual-funciona-melhor-para-mim\/\">Ciclo x Cronograma de Estudo: Qual funciona melhor para mim?<\/a><\/blockquote><iframe loading=\"lazy\" class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; clip: rect(1px, 1px, 1px, 1px);\" title=\"&#8220;Ciclo x Cronograma de Estudo: Qual funciona melhor para mim?&#8221; &#8212; Estrat\u00e9gia Concursos\" src=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/ciclo-x-cronograma-de-estudo-qual-funciona-melhor-para-mim\/embed\/#?secret=O6KtjAKbKM#?secret=jn89WbR3Dy\" data-secret=\"jn89WbR3Dy\" width=\"500\" height=\"282\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe>\n<\/div><figcaption><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/ciclo-x-cronograma-de-estudo-qual-funciona-melhor-para-mim\/\">https:\/\/www.estrategiaconcursos.com.br\/blog\/ciclo-x-cronograma-de-estudo-qual-funciona-melhor-para-mim\/<\/a><\/figcaption><\/figure>\n\n\n\n<p><a href=\"https:\/\/www.tcesc.tc.br\/\">https:\/\/www.tcesc.tc.br\/<\/a><\/p>\n\n\n\n<h2 class=\"has-text-align-center wp-block-heading\" id=\"h-cursos-e-assinaturas\">Cursos e Assinaturas<\/h2>\n\n\n\n<p><\/p>\n\n\n\n<p>Prepare-se com o melhor material e com quem mais aprova em Concursos P\u00fablicos em todo o pa\u00eds!<\/p>\n\n\n\n<div class=\"container\" id=\"boxes\">\n  <div class=\"row\">\n    <div class=\"col-sm\">\n      <div class=\"estrategia\" id=\"box-assinatura\">\n        <h3 class=\"titulo-assinatura\">Assinatura de Concursos<\/h3>\n        <p class=\"subtitulo-assinatura\">Assinatura de 1 ano ou 2 anos<\/p>\n        <div class=\"box-botao\">\n          <a class=\"btn-assinatura\" target=\"_blank\" href=\"https:\/\/www.estrategiaconcursos.com.br\/assinaturas\/\" role=\"button\" rel=\"noopener noreferrer\">ASSINE AGORA<\/a>\n        <\/div>\n      <\/div>\n      <p class=\"texto-auxiliar\"><\/p>\n    <\/div>\n    <div class=\"col-sm\">\n      <div class=\"questoes\" id=\"box-assinatura\">\n        <h3 class=\"titulo-assinatura\">Sistema de Quest\u00f5es<\/h3>\n        <p class=\"subtitulo-assinatura\">Assinatura de 1 ano ou 2 anos\n<\/p>\n        <div class=\"box-botao\">\n          <a class=\"btn-assinatura\" target=\"_blank\" href=\"https:\/\/www.estrategiaconcursos.com.br\/cursosPorConcurso\/sistema-de-questoes\/#\/\" role=\"button\" rel=\"noopener noreferrer\">ASSINE AGORA<\/a>\n        <\/div>\n      <\/div>\n      <p class=\"texto-auxiliar\"><\/p>\n    <\/div>\n  <\/div>\n<\/div>\n\n\n\n<div class=\"container\" id=\"boxes\">\n  <div class=\"row\">\n\n    <div class=\"col-sm\" id=\"boxes-concursos\">\n      <div style=\"background-color: #005DAD;\" class=\"conteudo-concursos\" id=\"box-concursos\">\n        <h3 class=\"titulo-assinatura\">Concursos Abertos<\/h3>\n        <p class=\"subtitulo-assinatura\">mais de 15 mil vagas<\/p>\n        <div class=\"box-botao\">\n          <a class=\"btn-assinatura\" target=\"_blank\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-abertos\/\" role=\"button\" rel=\"noopener noreferrer\">Conhe\u00e7a Agora<\/a>\n        <\/div>\n      <\/div>\n    <\/div>\n\n    \n\n    <div class=\"col-sm\" id=\"boxes-concursos\">\n      <div style=\"background-color: #419FF0;\" class=\"conteudo-concursos\" id=\"box-concursos\">\n        <h3 class=\"titulo-assinatura\">Concursos 2021<\/h3>\n        <p class=\"subtitulo-assinatura\">mais de 17 mil vagas<\/p>\n        <div class=\"box-botao\">\n          <a class=\"btn-assinatura\" target=\"_blank\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-2021\/\" role=\"button\" rel=\"noopener noreferrer\">Conhe\u00e7a Agora<\/a>\n        <\/div>\n      <\/div>\n    <\/div>\n\n  <\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Ol\u00e1, tudo bem com voc\u00ea? No artigo de hoje vamos fazer uma an\u00e1lise estat\u00edstica do novo concurso do TCE SC: para voc\u00ea ser aprovado. Vamos l\u00e1? Foi&nbsp;publicado o edital&nbsp;para o novo concurso do Tribunal de Contas de Santa Catarina (TCE-SC)! S\u00e3o 40 vagas imediatas mais 120 para forma\u00e7\u00e3o de cadastro reserva para o cargo de [&hellip;]<\/p>\n","protected":false},"author":773,"featured_media":40118,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"post_tipo":"article","footnotes":""},"categories":[214710],"tags":[],"tax_estado":[219987],"class_list":["post-907972","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tribunais-de-contas","tax_estado-sc"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.2 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>An\u00e1lise estat\u00edstica do TCE SC: para voc\u00ea ser aprovado<\/title>\n<meta name=\"description\" content=\"An\u00e1lise estat\u00edstica do TCE SC: para voc\u00ea ser aprovado, como ser aprovado nas diversas \u00e1reas do novo concurso para o tribunal de contas\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/analise-estatistica-do-tce-sc\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"An\u00e1lise estat\u00edstica do TCE SC: para voc\u00ea ser aprovado\" \/>\n<meta property=\"og:description\" content=\"An\u00e1lise estat\u00edstica do TCE SC: para voc\u00ea ser aprovado, como ser aprovado nas diversas \u00e1reas do novo concurso para o tribunal de contas\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/analise-estatistica-do-tce-sc\/\" \/>\n<meta property=\"og:site_name\" content=\"Estrat\u00e9gia Concursos\" \/>\n<meta property=\"article:published_time\" content=\"2021-11-22T11:24:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-11-24T23:24:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2016\/05\/30001821\/tce_nova_sede_versao_menor_foto_douglas_santos_acom_tce_sc.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"714\" \/>\n\t<meta property=\"og:image:height\" content=\"928\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Leonardo Mathias\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:site\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Leonardo Mathias\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/analise-estatistica-do-tce-sc\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/analise-estatistica-do-tce-sc\/\"},\"author\":{\"name\":\"Leonardo Mathias\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/ffa1e327b35698a5329b293a0627bd55\"},\"headline\":\"An\u00e1lise estat\u00edstica do TCE SC: para voc\u00ea ser aprovado\",\"datePublished\":\"2021-11-22T11:24:00+00:00\",\"dateModified\":\"2021-11-24T23:24:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/analise-estatistica-do-tce-sc\/\"},\"wordCount\":1852,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/analise-estatistica-do-tce-sc\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2016\/05\/30001821\/tce_nova_sede_versao_menor_foto_douglas_santos_acom_tce_sc.jpeg\",\"articleSection\":[\"Tribunais de Contas (TCU, TCE, TCM)\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/analise-estatistica-do-tce-sc\/#respond\"]}],\"copyrightYear\":\"2021\",\"copyrightHolder\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/analise-estatistica-do-tce-sc\/\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/analise-estatistica-do-tce-sc\/\",\"name\":\"An\u00e1lise estat\u00edstica do TCE SC: para voc\u00ea ser aprovado\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/analise-estatistica-do-tce-sc\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/analise-estatistica-do-tce-sc\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2016\/05\/30001821\/tce_nova_sede_versao_menor_foto_douglas_santos_acom_tce_sc.jpeg\",\"datePublished\":\"2021-11-22T11:24:00+00:00\",\"dateModified\":\"2021-11-24T23:24:11+00:00\",\"description\":\"An\u00e1lise estat\u00edstica do TCE SC: para voc\u00ea ser aprovado, como ser aprovado nas diversas \u00e1reas do novo concurso para o tribunal de contas\",\"breadcrumb\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/analise-estatistica-do-tce-sc\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/analise-estatistica-do-tce-sc\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/analise-estatistica-do-tce-sc\/#primaryimage\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2016\/05\/30001821\/tce_nova_sede_versao_menor_foto_douglas_santos_acom_tce_sc.jpeg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2016\/05\/30001821\/tce_nova_sede_versao_menor_foto_douglas_santos_acom_tce_sc.jpeg\",\"width\":714,\"height\":928,\"caption\":\"An\u00e1lise estat\u00edstica do TCE SC\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/analise-estatistica-do-tce-sc\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"An\u00e1lise estat\u00edstica do TCE SC: para voc\u00ea ser aprovado\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"name\":\"Estrat\u00e9gia Concursos\",\"description\":\"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.\",\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\",\"name\":\"Estrat\u00e9gia Concursos\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"width\":230,\"height\":60,\"caption\":\"Estrat\u00e9gia Concursos\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/EstratConcursos\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/ffa1e327b35698a5329b293a0627bd55\",\"name\":\"Leonardo Mathias\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/f02a0a4304a1537239604f568c9b6a69a3a7bbd6a5033b760cb4a5697f00295b?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/f02a0a4304a1537239604f568c9b6a69a3a7bbd6a5033b760cb4a5697f00295b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/f02a0a4304a1537239604f568c9b6a69a3a7bbd6a5033b760cb4a5697f00295b?s=96&d=mm&r=g\",\"caption\":\"Leonardo Mathias\"},\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/leonardomathiasestrategiaconcursos-com-br\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"An\u00e1lise estat\u00edstica do TCE SC: para voc\u00ea ser aprovado","description":"An\u00e1lise estat\u00edstica do TCE SC: para voc\u00ea ser aprovado, como ser aprovado nas diversas \u00e1reas do novo concurso para o tribunal de contas","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.estrategiaconcursos.com.br\/blog\/analise-estatistica-do-tce-sc\/","og_locale":"pt_BR","og_type":"article","og_title":"An\u00e1lise estat\u00edstica do TCE SC: para voc\u00ea ser aprovado","og_description":"An\u00e1lise estat\u00edstica do TCE SC: para voc\u00ea ser aprovado, como ser aprovado nas diversas \u00e1reas do novo concurso para o tribunal de contas","og_url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/analise-estatistica-do-tce-sc\/","og_site_name":"Estrat\u00e9gia Concursos","article_published_time":"2021-11-22T11:24:00+00:00","article_modified_time":"2021-11-24T23:24:11+00:00","og_image":[{"width":714,"height":928,"url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2016\/05\/30001821\/tce_nova_sede_versao_menor_foto_douglas_santos_acom_tce_sc.jpeg","type":"image\/jpeg"}],"author":"Leonardo Mathias","twitter_card":"summary_large_image","twitter_creator":"@EstratConcursos","twitter_site":"@EstratConcursos","twitter_misc":{"Escrito por":"Leonardo Mathias","Est. tempo de leitura":"8 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/analise-estatistica-do-tce-sc\/#article","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/analise-estatistica-do-tce-sc\/"},"author":{"name":"Leonardo Mathias","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/ffa1e327b35698a5329b293a0627bd55"},"headline":"An\u00e1lise estat\u00edstica do TCE SC: para voc\u00ea ser aprovado","datePublished":"2021-11-22T11:24:00+00:00","dateModified":"2021-11-24T23:24:11+00:00","mainEntityOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/analise-estatistica-do-tce-sc\/"},"wordCount":1852,"commentCount":0,"publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/analise-estatistica-do-tce-sc\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2016\/05\/30001821\/tce_nova_sede_versao_menor_foto_douglas_santos_acom_tce_sc.jpeg","articleSection":["Tribunais de Contas (TCU, TCE, TCM)"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/analise-estatistica-do-tce-sc\/#respond"]}],"copyrightYear":"2021","copyrightHolder":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/analise-estatistica-do-tce-sc\/","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/analise-estatistica-do-tce-sc\/","name":"An\u00e1lise estat\u00edstica do TCE SC: para voc\u00ea ser aprovado","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/analise-estatistica-do-tce-sc\/#primaryimage"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/analise-estatistica-do-tce-sc\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2016\/05\/30001821\/tce_nova_sede_versao_menor_foto_douglas_santos_acom_tce_sc.jpeg","datePublished":"2021-11-22T11:24:00+00:00","dateModified":"2021-11-24T23:24:11+00:00","description":"An\u00e1lise estat\u00edstica do TCE SC: para voc\u00ea ser aprovado, como ser aprovado nas diversas \u00e1reas do novo concurso para o tribunal de contas","breadcrumb":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/analise-estatistica-do-tce-sc\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/analise-estatistica-do-tce-sc\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/analise-estatistica-do-tce-sc\/#primaryimage","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2016\/05\/30001821\/tce_nova_sede_versao_menor_foto_douglas_santos_acom_tce_sc.jpeg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2016\/05\/30001821\/tce_nova_sede_versao_menor_foto_douglas_santos_acom_tce_sc.jpeg","width":714,"height":928,"caption":"An\u00e1lise estat\u00edstica do TCE SC"},{"@type":"BreadcrumbList","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/analise-estatistica-do-tce-sc\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.estrategiaconcursos.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"An\u00e1lise estat\u00edstica do TCE SC: para voc\u00ea ser aprovado"}]},{"@type":"WebSite","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","name":"Estrat\u00e9gia Concursos","description":"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.","publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization","name":"Estrat\u00e9gia Concursos","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","width":230,"height":60,"caption":"Estrat\u00e9gia Concursos"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/EstratConcursos"]},{"@type":"Person","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/ffa1e327b35698a5329b293a0627bd55","name":"Leonardo Mathias","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/f02a0a4304a1537239604f568c9b6a69a3a7bbd6a5033b760cb4a5697f00295b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f02a0a4304a1537239604f568c9b6a69a3a7bbd6a5033b760cb4a5697f00295b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f02a0a4304a1537239604f568c9b6a69a3a7bbd6a5033b760cb4a5697f00295b?s=96&d=mm&r=g","caption":"Leonardo Mathias"},"url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/leonardomathiasestrategiaconcursos-com-br\/"}]}},"_links":{"self":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/907972","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/users\/773"}],"replies":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/comments?post=907972"}],"version-history":[{"count":10,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/907972\/revisions"}],"predecessor-version":[{"id":915782,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/907972\/revisions\/915782"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media\/40118"}],"wp:attachment":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media?parent=907972"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/categories?post=907972"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tags?post=907972"},{"taxonomy":"tax_estado","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tax_estado?post=907972"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}