{"id":907571,"date":"2025-06-18T10:41:00","date_gmt":"2025-06-18T13:41:00","guid":{"rendered":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?p=907571"},"modified":"2025-06-18T17:47:01","modified_gmt":"2025-06-18T20:47:01","slug":"concurso-guarda-de-goiania","status":"publish","type":"post","link":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-guarda-de-goiania\/","title":{"rendered":"Concurso Guarda de Goi\u00e2nia: 700 vagas! Comiss\u00e3o formada"},"content":{"rendered":"\n<p style=\"font-size:clamp(15.197px, 0.95rem + ((1vw - 3.2px) * 0.765), 23px);\"><em><strong>Novo edital do concurso GCM Goi\u00e2nia deve ser publicado em 2025!<\/strong><\/em><\/p>\n\n\n\n<p>O pr\u00f3ximo <strong>concurso Guarda de Goi\u00e2nia<\/strong> deve ocorrer em breve! Isso porque o edital j\u00e1 est\u00e1 oficialmente autorizado e a comiss\u00e3o respons\u00e1vel est\u00e1 formada.<\/p>\n\n\n\n<p>Segundo o despacho de autoriza\u00e7\u00e3o, s\u00e3o previstas <strong>700 vagas<\/strong> para a carreira, sendo 100 vagas para provimento imediato e 600 destinadas \u00e0 forma\u00e7\u00e3o de cadastro de reserva.<\/p>\n\n\n\n<p>Entre os principais requisitos est\u00e3o a escolaridade de n\u00edvel superior, idade de 18 a 35 anos e Carteira Nacional de Habilita\u00e7\u00e3o, na categoria AB. Segundo o Plano de Cargos, o subs\u00eddio ser\u00e1 de R$ 3,7 mil.<\/p>\n\n\n\n<ul class=\"wp-block-list has-very-light-gray-to-cyan-bluish-gray-gradient-background has-background\">\n<li><strong>Guarda de Goi\u00e2nia<\/strong><\/li>\n\n\n\n<li><strong>Situa\u00e7\u00e3o<\/strong>: comiss\u00e3o formada<\/li>\n\n\n\n<li><strong>Banca: <\/strong>a definir<\/li>\n\n\n\n<li><strong style=\"background-color: initial; color: initial;\">Vagas<\/strong><span style=\"background-color: initial; color: initial;\">: 100 + 600 CR<\/span><\/li>\n\n\n\n<li><strong>Sal\u00e1rio<\/strong>: R$ 3.700,00<\/li>\n\n\n\n<li><strong>\u00daltimo edital:<\/strong> <a href=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/11\/12160823\/edital_guarda_-_publicado_no_d-o-m.pdf\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">Guarda de Goi\u00e2nia 2005<\/a><\/li>\n<\/ul>\n\n\n\n<p>Conv\u00e9m relembrar que a \u00faltima sele\u00e7\u00e3o ocorreu em 2005, onde foram ofertadas 1.000 vagas para o cargo de Guarda Municipal, sendo 900 para o sexo masculino e 100 para o sexo feminino.<\/p>\n\n\n\n<p>A fim de te deixar sempre bem informado, elaboramos este artigo com as principais informa\u00e7\u00f5es e novidades sobre o concurso Guarda de Goi\u00e2nia. Acompanhe os t\u00f3picos abaixo e n\u00e3o perca nenhum detalhe: <\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"#situ\">Situa\u00e7\u00e3o atual do concurso<\/a>\n<ul class=\"wp-block-list\">\n<li><a href=\"#comissao\">Comiss\u00e3o formada<\/a><\/li>\n\n\n\n<li><a href=\"#h-autorizacao\">Autoriza\u00e7\u00e3o<\/a><\/li>\n\n\n\n<li><a href=\"#confirmado\">Concurso confirmado<\/a><\/li>\n<\/ul>\n<\/li>\n\n\n\n<li><a href=\"#sobre-cargo\">Sobre o cargo de Guarda Municipal<\/a>\n<ul class=\"wp-block-list\">\n<li><a href=\"#requisitos\">Requisitos<\/a><\/li>\n\n\n\n<li><a href=\"#remuneracao\">Tabela de remunera\u00e7\u00e3o<\/a><\/li>\n\n\n\n<li><a href=\"#atribuicoes\">Atribui\u00e7\u00f5es<\/a><\/li>\n<\/ul>\n<\/li>\n\n\n\n<li><a href=\"#ultimo\">\u00daltimo concurso<\/a>\n<ul class=\"wp-block-list\">\n<li><a href=\"#etapa\">Etapas do \u00faltimo edital<\/a><\/li>\n<\/ul>\n<\/li>\n\n\n\n<li><a href=\"#curso\">Cursos e assinaturas<\/a><\/li>\n\n\n\n<li><a href=\"#ficha\">Ficha t\u00e9cnica<\/a><\/li>\n<\/ul>\n\n\n\n<div class=\"container\" id=\"boxes\">\n  <div class=\"row\">\n\n    <div class=\"col-sm\">\n      <div class=\"banner-guarda-gcm\" id=\"box-assinatura\">\n        <h3 class=\"titulo-assinatura\">Concurso Guarda de Goi\u00e2nia<\/h3>\n        <p class=\"subtitulo-assinatura\">Conhe\u00e7a os cursos<\/p>\n        <div class=\"box-botao\">\n          <a class=\"btn-assinatura\" target=\"_blank\" href=\"https:\/\/www.estrategiaconcursos.com.br\/curso\/prefeitura-de-goiania-gcm-goiania-guarda-civil-municipal-pacote\/\" role=\"button\" rel=\"noopener noreferrer\">Conhe\u00e7a mais<\/a>\n        <\/div>\n      <\/div>\n     \n    <\/div>\n\n  <\/div>\n<\/div>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"situ\">Situa\u00e7\u00e3o atual do concurso Guarda de Goi\u00e2nia<\/h2>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"comissao\">Comiss\u00e3o formada<\/h3>\n\n\n\n<p>A <strong>Prefeitura de Goi\u00e2nia<\/strong> deu mais um grande passo para a viabiliza\u00e7\u00e3o e realiza\u00e7\u00e3o de seu novo concurso para Guarda Municipal. Isso porque a comiss\u00e3o de estudos foi oficialmente formada.<\/p>\n\n\n\n<p>Conforme o que consta no Di\u00e1rio Oficial do Munic\u00edpio, foram designados <strong>21 servidores<\/strong> de diferentes secretarias municipais para iniciar a elabora\u00e7\u00e3o do relat\u00f3rio final e do termo de refer\u00eancia.<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"858\" height=\"587\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/08\/27222743\/image-604.png\" alt=\"Comiss\u00e3o formada do concurso GCM Goi\u00e2nia\" class=\"wp-image-1452201\" style=\"width:638px;height:auto\" srcset=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/08\/27222743\/image-604.png 858w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/08\/27222743\/image-604-300x205.png 300w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/08\/27222743\/image-604-768x525.png 768w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/08\/27222743\/image-604-610x417.png 610w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/08\/27222743\/image-604-150x103.png 150w\" sizes=\"auto, (max-width: 858px) 100vw, 858px\" \/><figcaption class=\"wp-element-caption\">Comiss\u00e3o formada do concurso GCM Goi\u00e2nia<\/figcaption><\/figure>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/08\/27214145\/comissao-formada.pdf\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">Veja aqui a \u00edntegra da comiss\u00e3o<\/a><\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-autorizacao-do-concurso-gcm-goiania\">Autoriza\u00e7\u00e3o do concurso GCM Goi\u00e2nia<\/h3>\n\n\n\n<p>Foi assinado pelo prefeito Rog\u00e9rio Cruz, em 10 de setembro de 2024, a autoriza\u00e7\u00e3o para a realiza\u00e7\u00e3o do novo concurso para a institui\u00e7\u00e3o.<\/p>\n\n\n\n<p>A sele\u00e7\u00e3o deve ofertar o provimento de 700 vagas, sendo 100 para provimento imediato e 600 destinadas \u00e0 forma\u00e7\u00e3o de cadastro de reserva.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"previsao\">Concurso confirmado<\/h3>\n\n\n\n<p>Com objetivo de aumentar o efetivo da Guarda Municipal da cidade de Goi\u00e2nia, bem como a sensa\u00e7\u00e3o de seguran\u00e7a por parte da popula\u00e7\u00e3o, Rog\u00e9rio confirmou um novo concurso.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"sobre-cargo\">Sobre o cargo de Guarda Municipal de Goi\u00e2nia<\/h2>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"requisitos\">Requisitos<\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li>I \u2013 nacionalidade brasileira;<\/li>\n\n\n\n<li>II \u2013 gozo de direitos pol\u00edticos;<\/li>\n\n\n\n<li>III \u2013 quita\u00e7\u00e3o com as obriga\u00e7\u00f5es militares e eleitorais;<\/li>\n\n\n\n<li>IV \u2013 possuir certificado ou diploma de conclus\u00e3o de <strong>Ensino Superior<\/strong>;<\/li>\n\n\n\n<li>V \u2013 idade de <strong>18 a 35 anos<\/strong>;<\/li>\n\n\n\n<li>VI \u2013 altura m\u00ednima de 1,60m (se mulher) e 1,65m (se homem);<\/li>\n\n\n\n<li>VII \u2013 aptid\u00e3o plena f\u00edsica e psicol\u00f3gica e n\u00e3o ser usu\u00e1rio de subst\u00e2ncia proibida por lei;<\/li>\n\n\n\n<li>VIII \u2013 boa sa\u00fade f\u00edsica e mental, comprovada em inspe\u00e7\u00e3o pela per\u00edcia m\u00e9dica oficial;<\/li>\n\n\n\n<li>IX \u2013 <strong>habilita\u00e7\u00e3o para conduzir ve\u00edculos<\/strong>, no m\u00ednimo, nas categorias AB;<\/li>\n\n\n\n<li>X \u2013 boa conduta social e idoneidade moral, comprovada por investiga\u00e7\u00e3o social e certid\u00f5es expedidas perante Tribunais de Contas do Munic\u00edpio, Estado e Uni\u00e3o e o Poder Judici\u00e1rio estadual, federal e distrital;<\/li>\n\n\n\n<li>XI \u2013 n\u00e3o possuir antecedentes criminais.<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"tabela-de-remuneracao\">Tabela de remunera\u00e7\u00e3o<\/h3>\n\n\n\n<p>Segundo o atual <a href=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/06\/13093246\/do_20220610_000007817.pdf\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">Plano de Cargos, Carreiras e Vencimentos dos servidores da Guarda Municipal<\/a>, confira na tabela abaixo os sal\u00e1rios:<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter\"><img decoding=\"async\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/06\/13091437\/image-170.png\" alt=\"Plano de vencimentos da Guarda de Goi\u00e2nia\"\/><figcaption class=\"wp-element-caption\">Plano de remunera\u00e7\u00f5es da Guarda Municipal de Goi\u00e2nia<\/figcaption><\/figure>\n\n\n\n<p>Os servidores ainda contam com aux\u00edlio alimenta\u00e7\u00e3o e gratifica\u00e7\u00e3o por desempenho da fun\u00e7\u00e3o. No entanto, conv\u00e9m frisar que o sal\u00e1rio inicial ser\u00e1 de R$ 3,7 mil, segundo informa\u00e7\u00f5es do comandante Wellington Paranhos.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"atribuicoes\">Atribui\u00e7\u00f5es<\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li>I \u2013 realizar atividades de natureza policial envolvendo a fiscaliza\u00e7\u00e3o, patrulhamento e policiamento ostensivo, atendimento e socorro a popula\u00e7\u00e3o;<\/li>\n\n\n\n<li>II \u2013 executar as atividades administrativas de rotina, t\u00e9cnicas e especializadas e as operacionais da corpora\u00e7\u00e3o;<\/li>\n\n\n\n<li>III \u2013 proteger os bens, servi\u00e7os e instala\u00e7\u00f5es;<\/li>\n\n\n\n<li>IV \u2013 atuar como agente de defesa civil e no caso de calamidades p\u00fablicas;<\/li>\n\n\n\n<li>V \u2013 realizar a\u00e7\u00f5es de pol\u00edcia administrativa quando lhes forem delegadas;<\/li>\n\n\n\n<li>VI \u2013 colaborar com as autoridades no policiamento preventivo e comunit\u00e1rio, a p\u00e9 ou motorizado; <\/li>\n\n\n\n<li>VII \u2013 deter e conduzir a presen\u00e7a da autoridade policial que ou quem for encontrado em situa\u00e7\u00e3o de flagrante delito;<\/li>\n\n\n\n<li>VIII \u2013 proteger o patrim\u00f4nio ambiental da cidade conforme legisla\u00e7\u00e3o vigente;<\/li>\n\n\n\n<li>IX \u2013 inteirar-se das normas e publica\u00e7\u00f5es espec\u00edficas referentes ao desempenho da fun\u00e7\u00e3o;<\/li>\n\n\n\n<li>X \u2013 comparecer e frequentar os cursos para os quais for convocado;<\/li>\n\n\n\n<li>XI \u2013 executar as ordens legais vindas de seus superiores;<\/li>\n\n\n\n<li>XII \u2013 prestar aux\u00edlio \u00e0 popula\u00e7\u00e3o;<\/li>\n\n\n\n<li>XIII \u2013 redigir, registrar, escriturar, avaliar e encaminhar toda a documenta\u00e7\u00e3o correlata com sua fun\u00e7\u00e3o, principalmente os relat\u00f3rios de ocorr\u00eancias, os de atendimentos e os livros de passagem de servi\u00e7o;<\/li>\n\n\n\n<li>XIV \u2013 conduzir os ve\u00edculos da aprova\u00e7\u00e3o em processo de avalia\u00e7\u00e3o, possuir curso de dire\u00e7\u00e3o defensiva de ve\u00edculo em situa\u00e7\u00e3o de emerg\u00eancia;<\/li>\n\n\n\n<li>XV \u2013 orientar, pacificar, controlar, fiscalizar, autuar, apreender e interditar;<\/li>\n\n\n\n<li>XVI \u2013 realizar outras atribui\u00e7\u00f5es ou fun\u00e7\u00e3o, designadas pelos Comandantes.<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"ultimo\">\u00daltimo concurso Guarda de Goi\u00e2nia<\/h2>\n\n\n\n<p>O \u00faltimo edital do concurso Guarda de Goi\u00e2nia aconteceu em 2005, com a oferta de 1.000 vagas, sendo 900 para o sexo masculino e 100 para o sexo feminino, com a exig\u00eancia de n\u00edvel fundamental completo.<\/p>\n\n\n\n<p>Na \u00e9poca, a remunera\u00e7\u00e3o inicial foi fixada no valor de R$ 584,64 + gratifica\u00e7\u00f5es.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"etapa\">Etapas do \u00faltimo concurso Guarda de Goi\u00e2nia<\/h3>\n\n\n\n<p>O \u00faltimo concurso Guarda de Goi\u00e2nia foi composto por quatro etapas. Confira a seguir:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Prova Objetiva de car\u00e1ter eliminat\u00f3rio e classificat\u00f3rio;<\/li>\n\n\n\n<li>Avalia\u00e7\u00e3o M\u00e9dica de car\u00e1ter eliminat\u00f3rio;<\/li>\n\n\n\n<li>Teste de Aptid\u00e3o F\u00edsica (TAF) de car\u00e1ter eliminat\u00f3rio; e<\/li>\n\n\n\n<li>Avalia\u00e7\u00e3o Psicol\u00f3gica de car\u00e1ter eliminat\u00f3rio.<\/li>\n<\/ul>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"objetiva\">Prova Objetiva<\/h4>\n\n\n\n<p>A prova objetiva contou com 50 quest\u00f5es de m\u00faltipla escolha, valendo 2 pontos cada uma. Veja no quadro abaixo:<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"732\" height=\"222\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/11\/12160221\/image-221.png\" alt=\"Quadro com informa\u00e7\u00f5es da prova objetiva do \u00faltimo concurso\" class=\"wp-image-907634\" srcset=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/11\/12160221\/image-221.png 732w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/11\/12160221\/image-221-300x91.png 300w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/11\/12160221\/image-221-610x185.png 610w\" sizes=\"auto, (max-width: 732px) 100vw, 732px\" \/><figcaption class=\"wp-element-caption\">Quadro com informa\u00e7\u00f5es da prova objetiva do \u00faltimo concurso<\/figcaption><\/figure>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"taf\">Teste de Aptid\u00e3o F\u00edsica (TAF)<\/h4>\n\n\n\n<p>A Prova de Capacidade F\u00edsica de car\u00e1ter eliminat\u00f3rio, visou aferir a capacidade do candidato para suportar f\u00edsica e organicamente as exig\u00eancias das atribui\u00e7\u00f5es do cargo, e foi realizada pelos candidatos aprovados na 2\u00aa Etapa.<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"597\" height=\"145\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/11\/12160358\/image-223.png\" alt=\"Quadro de TAF do \u00faltimo concurso Guarda de Goi\u00e2nia\" class=\"wp-image-907639\" srcset=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/11\/12160358\/image-223.png 597w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/11\/12160358\/image-223-300x73.png 300w\" sizes=\"auto, (max-width: 597px) 100vw, 597px\" \/><figcaption class=\"wp-element-caption\">Quadro de TAF do \u00faltimo concurso Guarda de Goi\u00e2nia<\/figcaption><\/figure>\n\n\n\n<hr class=\"wp-block-separator has-css-opacity\"\/>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-center\" id=\"h-quer-saber-tudo-sobre-concursos-previstos-confira-nossos-artigos\">Quer saber tudo sobre concursos previstos?<br \/>Confira nossos artigos!<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-abertos\/\" target=\"_blank\" rel=\"noreferrer noopener\">Concursos abertos<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-2025\/\" target=\"_blank\" rel=\"noreferrer noopener\">Concursos 2025<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-2026\/\" target=\"_blank\" rel=\"noreferrer noopener\">Concursos 2026<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-guarda-municipal\/\" target=\"_blank\" rel=\"noreferrer noopener\">Concursos Guarda Municipal<\/a><\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-center\" id=\"curso\">Quer estudar para o concurso Guarda de Goi\u00e2nia?<\/h2>\n\n\n\n<div class=\"container\" id=\"boxes\">\n  <div class=\"row\">\n\n    <div class=\"col-sm\">\n      <div class=\"banner-guarda-gcm\" id=\"box-assinatura\">\n        <h3 class=\"titulo-assinatura\">Concurso Guarda de Goi\u00e2nia<\/h3>\n        <p class=\"subtitulo-assinatura\">Conhe\u00e7a os cursos<\/p>\n        <div class=\"box-botao\">\n          <a class=\"btn-assinatura\" target=\"_blank\" href=\"https:\/\/www.estrategiaconcursos.com.br\/curso\/prefeitura-de-goiania-gcm-goiania-guarda-civil-municipal-pacote\/\" role=\"button\" rel=\"noopener noreferrer\">Conhe\u00e7a mais<\/a>\n        <\/div>\n      <\/div>\n     \n    <\/div>\n\n  <\/div>\n<\/div>\n\n\n\n<div class=\"container\" id=\"boxes\">\n  <div class=\"row\">\n\n    <div class=\"col-sm\">\n      <div class=\"estrategia\" id=\"box-assinatura\">\n        <h3 class=\"titulo-assinatura\">Assinatura de Concursos<\/h3>\n        <p class=\"subtitulo-assinatura\">Assinatura de 1 ano ou 2 anos<\/p>\n        <div class=\"box-botao\">\n          <a class=\"btn-assinatura\" target=\"_blank\" href=\"https:\/\/www.estrategiaconcursos.com.br\/assinaturas\/\" role=\"button\" rel=\"noopener noreferrer\">ASSINE AGORA<\/a>\n        <\/div>\n      <\/div><\/div><\/div><\/div>\n\n\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"632\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/08\/03075659\/ficha-tecnica-1-1024x632.png\" alt=\"Ficha t\u00e9cnica\" class=\"wp-image-827472\" style=\"width:274px;height:auto\" srcset=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/08\/03075659\/ficha-tecnica-1-1024x632.png 1024w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/08\/03075659\/ficha-tecnica-1-300x185.png 300w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/08\/03075659\/ficha-tecnica-1-768x474.png 768w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/08\/03075659\/ficha-tecnica-1-1536x948.png 1536w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/08\/03075659\/ficha-tecnica-1-610x377.png 610w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/08\/03075659\/ficha-tecnica-1.png 1571w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"ficha\">Informa\u00e7\u00f5es do concurso Guarda de Goi\u00e2nia<\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Data prevista:<\/strong>&nbsp;2025<\/li>\n\n\n\n<li><strong>Vagas:&nbsp;<\/strong>100 + 600 CR<\/li>\n\n\n\n<li><strong>Cargo:<\/strong>&nbsp;Guarda Municipal<\/li>\n\n\n\n<li><strong>Escolaridade:&nbsp;<\/strong>n\u00edvel superior<\/li>\n\n\n\n<li><strong>Banca:&nbsp;<\/strong>a definir<\/li>\n\n\n\n<li><strong>\u00daltimo edital:<\/strong> <a href=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/11\/12160823\/edital_guarda_-_publicado_no_d-o-m.pdf\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">Guarda de Goi\u00e2nia 2005<\/a><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Novo edital do concurso GCM Goi\u00e2nia deve ser publicado em 2025! O pr\u00f3ximo concurso Guarda de Goi\u00e2nia deve ocorrer em breve! Isso porque o edital j\u00e1 est\u00e1 oficialmente autorizado e a comiss\u00e3o respons\u00e1vel est\u00e1 formada. Segundo o despacho de autoriza\u00e7\u00e3o, s\u00e3o previstas 700 vagas para a carreira, sendo 100 vagas para provimento imediato e 600 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":910788,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"post_tipo":"news_page","footnotes":""},"categories":[220189],"tags":[],"tax_estado":[219972],"class_list":["post-907571","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-policial-guarda-civis","tax_estado-go"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.2 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Concurso Guarda de Goi\u00e2nia: 700 vagas! Comiss\u00e3o formada<\/title>\n<meta name=\"description\" content=\"Concurso Guarda de Goi\u00e2nia: edital previsto com 700 vagas de n\u00edvel superior. Comiss\u00e3o est\u00e1 formada! Acesse e confira os detalhes!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-guarda-de-goiania\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Concurso Guarda de Goi\u00e2nia: 700 vagas! Comiss\u00e3o formada\" \/>\n<meta property=\"og:description\" content=\"Concurso Guarda de Goi\u00e2nia: edital previsto com 700 vagas de n\u00edvel superior. Comiss\u00e3o est\u00e1 formada! Acesse e confira os detalhes!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-guarda-de-goiania\/\" \/>\n<meta property=\"og:site_name\" content=\"Estrat\u00e9gia Concursos\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/EstrategiaConcursos\" \/>\n<meta property=\"article:published_time\" content=\"2025-06-18T13:41:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-06-18T20:47:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/11\/17160707\/guarda_de_goiania.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"768\" \/>\n\t<meta property=\"og:image:height\" content=\"432\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Coordena\u00e7\u00e3o\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:site\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Coordena\u00e7\u00e3o\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-guarda-de-goiania\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-guarda-de-goiania\/\"},\"author\":{\"name\":\"Coordena\u00e7\u00e3o\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/b4a388c97673c5f483d72185668afa1f\"},\"headline\":\"Concurso Guarda de Goi\u00e2nia: 700 vagas! Comiss\u00e3o formada\",\"datePublished\":\"2025-06-18T13:41:00+00:00\",\"dateModified\":\"2025-06-18T20:47:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-guarda-de-goiania\/\"},\"wordCount\":1186,\"commentCount\":3,\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-guarda-de-goiania\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/11\/17160707\/guarda_de_goiania.jpg\",\"articleSection\":[\"Policial (Guardas Civis)\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-guarda-de-goiania\/#respond\"]}],\"copyrightYear\":\"2025\",\"copyrightHolder\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-guarda-de-goiania\/\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-guarda-de-goiania\/\",\"name\":\"Concurso Guarda de Goi\u00e2nia: 700 vagas! Comiss\u00e3o formada\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-guarda-de-goiania\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-guarda-de-goiania\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/11\/17160707\/guarda_de_goiania.jpg\",\"datePublished\":\"2025-06-18T13:41:00+00:00\",\"dateModified\":\"2025-06-18T20:47:01+00:00\",\"description\":\"Concurso Guarda de Goi\u00e2nia: edital previsto com 700 vagas de n\u00edvel superior. Comiss\u00e3o est\u00e1 formada! Acesse e confira os detalhes!\",\"breadcrumb\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-guarda-de-goiania\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-guarda-de-goiania\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-guarda-de-goiania\/#primaryimage\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/11\/17160707\/guarda_de_goiania.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/11\/17160707\/guarda_de_goiania.jpg\",\"width\":768,\"height\":432,\"caption\":\"concurso Guarda de Goi\u00e2nia\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-guarda-de-goiania\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Concurso Guarda de Goi\u00e2nia: 700 vagas! Comiss\u00e3o formada\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"name\":\"Estrat\u00e9gia Concursos\",\"description\":\"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.\",\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\",\"name\":\"Estrat\u00e9gia Concursos\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"width\":230,\"height\":60,\"caption\":\"Estrat\u00e9gia Concursos\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/EstratConcursos\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/b4a388c97673c5f483d72185668afa1f\",\"name\":\"Coordena\u00e7\u00e3o\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/b720319e4c9a967eb58678d110f4fe35452fc5d5f97b202bac7b8acceb18c6ad?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/b720319e4c9a967eb58678d110f4fe35452fc5d5f97b202bac7b8acceb18c6ad?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/b720319e4c9a967eb58678d110f4fe35452fc5d5f97b202bac7b8acceb18c6ad?s=96&d=mm&r=g\",\"caption\":\"Coordena\u00e7\u00e3o\"},\"sameAs\":[\"https:\/\/www.facebook.com\/EstrategiaConcursos\",\"https:\/\/x.com\/EstratConcursos\"],\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/estrategia2013\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Concurso Guarda de Goi\u00e2nia: 700 vagas! Comiss\u00e3o formada","description":"Concurso Guarda de Goi\u00e2nia: edital previsto com 700 vagas de n\u00edvel superior. Comiss\u00e3o est\u00e1 formada! Acesse e confira os detalhes!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-guarda-de-goiania\/","og_locale":"pt_BR","og_type":"article","og_title":"Concurso Guarda de Goi\u00e2nia: 700 vagas! Comiss\u00e3o formada","og_description":"Concurso Guarda de Goi\u00e2nia: edital previsto com 700 vagas de n\u00edvel superior. Comiss\u00e3o est\u00e1 formada! Acesse e confira os detalhes!","og_url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-guarda-de-goiania\/","og_site_name":"Estrat\u00e9gia Concursos","article_author":"https:\/\/www.facebook.com\/EstrategiaConcursos","article_published_time":"2025-06-18T13:41:00+00:00","article_modified_time":"2025-06-18T20:47:01+00:00","og_image":[{"width":768,"height":432,"url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/11\/17160707\/guarda_de_goiania.jpg","type":"image\/jpeg"}],"author":"Coordena\u00e7\u00e3o","twitter_card":"summary_large_image","twitter_creator":"@EstratConcursos","twitter_site":"@EstratConcursos","twitter_misc":{"Escrito por":"Coordena\u00e7\u00e3o","Est. tempo de leitura":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-guarda-de-goiania\/#article","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-guarda-de-goiania\/"},"author":{"name":"Coordena\u00e7\u00e3o","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/b4a388c97673c5f483d72185668afa1f"},"headline":"Concurso Guarda de Goi\u00e2nia: 700 vagas! Comiss\u00e3o formada","datePublished":"2025-06-18T13:41:00+00:00","dateModified":"2025-06-18T20:47:01+00:00","mainEntityOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-guarda-de-goiania\/"},"wordCount":1186,"commentCount":3,"publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-guarda-de-goiania\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/11\/17160707\/guarda_de_goiania.jpg","articleSection":["Policial (Guardas Civis)"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-guarda-de-goiania\/#respond"]}],"copyrightYear":"2025","copyrightHolder":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-guarda-de-goiania\/","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-guarda-de-goiania\/","name":"Concurso Guarda de Goi\u00e2nia: 700 vagas! Comiss\u00e3o formada","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-guarda-de-goiania\/#primaryimage"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-guarda-de-goiania\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/11\/17160707\/guarda_de_goiania.jpg","datePublished":"2025-06-18T13:41:00+00:00","dateModified":"2025-06-18T20:47:01+00:00","description":"Concurso Guarda de Goi\u00e2nia: edital previsto com 700 vagas de n\u00edvel superior. Comiss\u00e3o est\u00e1 formada! Acesse e confira os detalhes!","breadcrumb":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-guarda-de-goiania\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-guarda-de-goiania\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-guarda-de-goiania\/#primaryimage","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/11\/17160707\/guarda_de_goiania.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/11\/17160707\/guarda_de_goiania.jpg","width":768,"height":432,"caption":"concurso Guarda de Goi\u00e2nia"},{"@type":"BreadcrumbList","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-guarda-de-goiania\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.estrategiaconcursos.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Concurso Guarda de Goi\u00e2nia: 700 vagas! Comiss\u00e3o formada"}]},{"@type":"WebSite","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","name":"Estrat\u00e9gia Concursos","description":"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.","publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization","name":"Estrat\u00e9gia Concursos","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","width":230,"height":60,"caption":"Estrat\u00e9gia Concursos"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/EstratConcursos"]},{"@type":"Person","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/b4a388c97673c5f483d72185668afa1f","name":"Coordena\u00e7\u00e3o","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/b720319e4c9a967eb58678d110f4fe35452fc5d5f97b202bac7b8acceb18c6ad?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b720319e4c9a967eb58678d110f4fe35452fc5d5f97b202bac7b8acceb18c6ad?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b720319e4c9a967eb58678d110f4fe35452fc5d5f97b202bac7b8acceb18c6ad?s=96&d=mm&r=g","caption":"Coordena\u00e7\u00e3o"},"sameAs":["https:\/\/www.facebook.com\/EstrategiaConcursos","https:\/\/x.com\/EstratConcursos"],"url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/estrategia2013\/"}]}},"_links":{"self":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/907571","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/comments?post=907571"}],"version-history":[{"count":29,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/907571\/revisions"}],"predecessor-version":[{"id":1593552,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/907571\/revisions\/1593552"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media\/910788"}],"wp:attachment":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media?parent=907571"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/categories?post=907571"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tags?post=907571"},{"taxonomy":"tax_estado","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tax_estado?post=907571"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}