{"id":884494,"date":"2021-10-17T18:45:00","date_gmt":"2021-10-17T21:45:00","guid":{"rendered":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?p=884494"},"modified":"2023-07-06T10:41:46","modified_gmt":"2023-07-06T13:41:46","slug":"resumo-itcmd-sefaz-sc","status":"publish","type":"post","link":"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-itcmd-sefaz-sc\/","title":{"rendered":"Resumo ITCMD para a SEFAZ SC \u2013 Analista Tribut\u00e1rio"},"content":{"rendered":"\n<p class=\"has-medium-font-size\">Veja as principais disposi\u00e7\u00f5es sobre a Lei 13.136\/04 e um resumo do ITCMD para a SEFAZ SC, concurso de Analista Tribut\u00e1rio 2021<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"870\" height=\"450\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/10\/14115351\/n_46517_e96d5e6d4b7386f182de7381a07cd06b__1_.jpg\" alt=\"Resumo ITCMD para a SEFAZ SC\" class=\"wp-image-884499\" srcset=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/10\/14115351\/n_46517_e96d5e6d4b7386f182de7381a07cd06b__1_.jpg 870w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/10\/14115351\/n_46517_e96d5e6d4b7386f182de7381a07cd06b__1_-300x155.jpg 300w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/10\/14115351\/n_46517_e96d5e6d4b7386f182de7381a07cd06b__1_-768x397.jpg 768w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/10\/14115351\/n_46517_e96d5e6d4b7386f182de7381a07cd06b__1_-610x316.jpg 610w\" sizes=\"auto, (max-width: 870px) 100vw, 870px\" \/><figcaption class=\"wp-element-caption\">Resumo ITCMD para a SEFAZ SC<\/figcaption><\/figure>\n\n\n\n<p>Ol\u00e1, Coruja! Tudo certo por a\u00ed?<\/p>\n\n\n\n<p>J\u00e1 domina as disposi\u00e7\u00f5es principais sobre o ITCMD para a SEFAZ SC? O ITCMD, Imposto sobre Transmiss\u00e3o de Causa Mortis e Doa\u00e7\u00f5es, tamb\u00e9m \u00e9 conhecido pela sigla ITCD em alguns Estados. Portanto, n\u00e3o se preocupe se ver uma ou outra nomenclatura. Saiba que ambas est\u00e3o corretas.<\/p>\n\n\n\n<p>Quando estudamos sobre esse tributo, o principal questionamento que temos \u00e9 sobre as diferen\u00e7as entre o ITCMD e o ITBI, aquele de compet\u00eancia estadual e este, municipal.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-diferencas-entre-itcmd-e-itbi\"><strong>Diferen\u00e7as entre ITCMD e ITBI<\/strong><\/h2>\n\n\n\n<p>Esses impostos s\u00e3o bastante confundidos uma vez que ambos incidem sobre a transmiss\u00e3o de bens entre indiv\u00edduos.<\/p>\n\n\n\n<p>A primeira diferen\u00e7a, como mencionado, \u00e9 sobre quem det\u00e9m a compet\u00eancia tribut\u00e1ria para a institui\u00e7\u00e3o. O ITCMD \u00e9 um tributo de compet\u00eancia dos Estados e do Distrito Federal, enquanto o ITBI \u00e9 de compet\u00eancia dos Munic\u00edpios e tamb\u00e9m do Distrito Federal.<\/p>\n\n\n\n<p>Outro ponto fundamental, o ITCMD incide sobre as transmiss\u00f5es a t\u00edtulo gratuito tanto de bens <strong>m\u00f3veis<\/strong> quanto de bens <strong>im\u00f3veis<\/strong>. Por outro lado, o ITBI incide nas transmiss\u00f5es onerosas sempre de bens <strong>im\u00f3veis.<\/strong><\/p>\n\n\n\n<p>Por \u00faltimo, as al\u00edquotas do ITCMD poder\u00e3o ser <strong>progressivas<\/strong>, isso quer dizer que quanto maior for a base de c\u00e1lculo maior ser\u00e1 a al\u00edquota. De acordo com a carta magna, cabe ao Senado Federal por meio de Resolu\u00e7\u00e3o fixar as al\u00edquotas m\u00e1ximas para este imposto.<\/p>\n\n\n\n<p>J\u00e1 em rela\u00e7\u00e3o ao ITBI, segundo a s\u00famula 656 do STF, \u00e9 inconstitucional o estabelecimento legal de al\u00edquotas progressivas para o ITBI.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-resumo-itcmd-para-a-sefaz-sc-analista-tributario\"><strong>Resumo ITCMD para a SEFAZ SC \u2013 Analista Tribut\u00e1rio<\/strong><\/h2>\n\n\n\n<p>Vejamos ent\u00e3o o resumo do ITCMD para a SEFAZ SC.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-fato-gerador\"><strong>Fato Gerador<\/strong><\/h3>\n\n\n\n<p>O Imposto sobre Transmiss\u00e3o \u201cCausa Mortis\u201d e Doa\u00e7\u00e3o de Quaisquer Bens ou Direitos &#8211; ITCMD, tem como fato gerador a transmiss\u00e3o \u201ccausa mortis\u201d ou a doa\u00e7\u00e3o, a qualquer t\u00edtulo, de:&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>i. propriedade ou dom\u00ednio \u00fatil de bem im\u00f3vel;<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>ii.&nbsp;direitos reais sobre bens m\u00f3veis e im\u00f3veis; e<\/li>\n\n\n\n<li>iii.&nbsp;bens m\u00f3veis, inclusive semoventes, direitos, t\u00edtulos e cr\u00e9ditos.<\/li>\n\n\n\n<li>iv. <strong>na sucess\u00e3o provis\u00f3ria<\/strong>, garantido o direito de restitui\u00e7\u00e3o, corrigida monetariamente, caso apare\u00e7a o ausente;<\/li>\n\n\n\n<li>v.&nbsp;na partilha antecipada prevista no art. 2.018 do C\u00f3digo Civil;<\/li>\n\n\n\n<li>vi. na partilha desigual do patrim\u00f4nio comum, quanto aos bens e direitos atribu\u00eddos a um dos c\u00f4njuges separados ou divorciados, ou cujo casamento foi anulado, ao companheiro(a) em uni\u00e3o est\u00e1vel devidamente reconhecida, acima da respectiva mea\u00e7\u00e3o;<\/li>\n\n\n\n<li>vii. na desist\u00eancia \u00e0 heran\u00e7a aceita, t\u00e1cita ou expressamente, ainda que antes da homologa\u00e7\u00e3o da partilha;<\/li>\n\n\n\n<li>viii.&nbsp;na ren\u00fancia \u00e0 sucess\u00e3o aberta, em favor de benefici\u00e1rio determinado.<\/li>\n<\/ul>\n\n\n\n<p><strong>Adendos:<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Considera-se doa\u00e7\u00e3o qualquer ato ou fato, n\u00e3o oneroso, que importe ou se resolva em transmiss\u00e3o de quaisquer bens ou direitos<\/li>\n\n\n\n<li>Nas transmiss\u00f5es \u201ccausa mortis\u201d e nas doa\u00e7\u00f5es ou cess\u00f5es ocorrem tantos fatos geradores quantos forem os herdeiros, legat\u00e1rios, donat\u00e1rios ou cession\u00e1rios.<\/li>\n\n\n\n<li>Nas transmiss\u00f5es de direitos reais sobre bens m\u00f3veis e im\u00f3veis ocorre o fato gerador na <strong>institui\u00e7\u00e3o<\/strong> e na <strong>extin\u00e7\u00e3o<\/strong> da superf\u00edcie, da servid\u00e3o, do usufruto, do uso e da habita\u00e7\u00e3o. (isto \u00e9, ocorre o FG no in\u00edcio e no fim.)<\/li>\n<\/ul>\n\n\n\n<p>Al\u00e9m das hip\u00f3teses de incid\u00eancia, o art. 2\u00ba do RITCMD disp\u00f5e que o imposto \u00e9 devido:<\/p>\n\n\n\n<p>I.&nbsp;Em se tratando de bens im\u00f3veis e respectivos direitos, quando situados no territ\u00f3rio deste Estado;<\/p>\n\n\n\n<p>II.&nbsp;Em se tratando de bens m\u00f3veis, direitos, t\u00edtulos e cr\u00e9ditos, quando:<\/p>\n\n\n\n<p>a. &nbsp; &nbsp; &nbsp; O invent\u00e1rio ou arrolamento se processar neste Estado; ou<\/p>\n\n\n\n<p>b.&nbsp; &nbsp; &nbsp; O doador for domiciliado neste Estado.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-resumo-itcmd-sefaz-sc-contribuintes\"><strong>Resumo ITCMD SEFAZ SC \u2013 Contribuintes<\/strong><\/h3>\n\n\n\n<p>S\u00e3o contribuintes do imposto:<\/p>\n\n\n\n<p>I &#8211; o herdeiro, o legat\u00e1rio, o fiduci\u00e1rio ou o fideicomiss\u00e1rio, no caso de transmiss\u00e3o \u201ccausa mortis\u201d;<\/p>\n\n\n\n<p>II &#8211; o donat\u00e1rio ou o cession\u00e1rio, no caso de doa\u00e7\u00e3o ou de cess\u00e3o;<\/p>\n\n\n\n<p>III &#8211; o benefici\u00e1rio de direito real, quando de sua institui\u00e7\u00e3o; e<\/p>\n\n\n\n<p>IV &#8211; o nu-propriet\u00e1rio, na extin\u00e7\u00e3o da superf\u00edcie, da servid\u00e3o, do usufruto, do uso e da habita\u00e7\u00e3o.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-base-de-calculo-do-itcmd-sefaz-sc\"><strong>Base de C\u00e1lculo do ITCMD \u2013 SEFAZ SC<\/strong><\/h3>\n\n\n\n<p>A base de c\u00e1lculo do imposto \u00e9 o <strong>valor venal<\/strong> dos bens ou direitos, dos t\u00edtulos ou dos cr\u00e9ditos transmitidos ou doados.<\/p>\n\n\n\n<p>Contudo, na institui\u00e7\u00e3o e na extin\u00e7\u00e3o de <strong>direito real<\/strong> sobre bens <strong>im\u00f3veis<\/strong>, bem como na transmiss\u00e3o da nua-propriedade, a base de c\u00e1lculo do imposto ser\u00e1 <strong>reduzida para 50<\/strong>% do valor venal do bem.<\/p>\n\n\n\n<p>Outra observa\u00e7\u00e3o \u00e9 em rela\u00e7\u00e3o a transmiss\u00e3o de valores mobili\u00e1rios (t\u00edtulos do governo, a\u00e7\u00f5es, renda fixa &#8230;). Nesses casos, a base de c\u00e1lculo ser\u00e1 o da cota\u00e7\u00e3o oficial do dia da avalia\u00e7\u00e3o.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-aliquotas-do-itcmd-sefaz-sc\"><strong>Al\u00edquotas do ITCMD SEFAZ SC<\/strong><\/h3>\n\n\n\n<p>Lembra-se de que as al\u00edquotas do ITCMD poder\u00e3o ser progressivas? Pois bem, em SC elas realmente s\u00e3o. Nesse sentido, quanto maior o valor do bem, maior a % de imposto que incidir\u00e1 sobre ele (princ\u00edpio da capacidade contributiva).<\/p>\n\n\n\n<p>As al\u00edquotas do imposto s\u00e3o:<\/p>\n\n\n\n<p>I. 1% sobre a parcela da base de c\u00e1lculo igual ou inferior a R$ 20.000,00;<\/p>\n\n\n\n<p>II. 3% sobre a parcela da base de c\u00e1lculo que exceder a R$ 20.000,00 e for igual ou inferior a R$ 50.000,00;<\/p>\n\n\n\n<p>III. 5% sobre a parcela da base de c\u00e1lculo que exceder a R$ 50.000,00 e for igual ou inferior a R$ 150.000,00;<\/p>\n\n\n\n<p>IV. 7% sobre a parcela da base de c\u00e1lculo que exceder a R$ 150.000,00;<\/p>\n\n\n\n<p>V. 8% sobre a base de c\u00e1lculo, quando:<\/p>\n\n\n\n<p>1. o sucessor for:<\/p>\n\n\n\n<p>i. parente colateral; ou<\/p>\n\n\n\n<p>&nbsp;ii. herdeiro testament\u00e1rio ou legat\u00e1rio que n\u00e3o tiver rela\u00e7\u00e3o de parentesco com o \u201cde cujus\u201d;<\/p>\n\n\n\n<p>2. o donat\u00e1rio ou o cession\u00e1rio:<\/p>\n\n\n\n<p>i. for parente colateral; ou<\/p>\n\n\n\n<p>&nbsp;ii. n\u00e3o tiver rela\u00e7\u00e3o de parentesco com o doador ou o cedente.<\/p>\n\n\n\n<p>Exemplo: doa\u00e7\u00e3o de R$ 200.000. Iremos quebrar esses 200 mil reais em 4 montantes:<\/p>\n\n\n\n<p>a. &nbsp; &nbsp; &nbsp; os Primeiros 20.000<\/p>\n\n\n\n<p>b.&nbsp; &nbsp; &nbsp; os pr\u00f3ximos 30.000 (para chegar aos 50.000 : 20.000 + 30.000)<\/p>\n\n\n\n<p>c. &nbsp; &nbsp; &nbsp; os pr\u00f3ximos 100.000 (para chegar aos 150.000: soma dos 50.000 anteriores mais 100.000)<\/p>\n\n\n\n<p>d.&nbsp; &nbsp; &nbsp; os 50.000 restantes para completar os 200.000<\/p>\n\n\n\n<p>1. &nbsp; &nbsp; &nbsp; Al\u00edquota 1% sobre 20.000 = R$ 200,00<\/p>\n\n\n\n<p>2. &nbsp; &nbsp; &nbsp; Al\u00edquota 3% sobre 30.000 = R$ 900,00<\/p>\n\n\n\n<p>3. &nbsp; &nbsp; &nbsp; Al\u00edquota 5% sobre 100.000 = R$ 5.000,00<\/p>\n\n\n\n<p>4. &nbsp; &nbsp; &nbsp; Al\u00edquota 7% sobre 50.000 = R$ R$ 3.500,00<\/p>\n\n\n\n<p>Total devido = R$ 9.600,00<\/p>\n\n\n\n<p>Obs.: Para fins de c\u00e1lculo do imposto, na hip\u00f3tese de sucessivas doa\u00e7\u00f5es, ou cess\u00f5es entre <strong>o mesmo doador ou cedente e o mesmo donat\u00e1rio ou cession\u00e1rio<\/strong>, ser\u00e3o consideradas todas as transmiss\u00f5es realizadas a esse t\u00edtulo, <strong>nos \u00faltimos doze meses<\/strong>, devendo o imposto ser recalculado a cada nova doa\u00e7\u00e3o ou cess\u00e3o, adicionando-se \u00e0 base de c\u00e1lculo os valores anteriormente submetidos \u00e0 tributa\u00e7\u00e3o, deduzindo-se os valores dos impostos j\u00e1 recolhidos.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-isencoes-do-itcmd\"><strong>Isen\u00e7\u00f5es do ITCMD<\/strong><\/h3>\n\n\n\n<p>A fim de calcular o montante devido, \u00e9 imprescind\u00edvel tamb\u00e9m que se saiba as hip\u00f3teses de isen\u00e7\u00e3o do imposto.<\/p>\n\n\n\n<p>Veja o que o <a href=\"https:\/\/legislacao.sef.sc.gov.br\/Consulta\/Views\/Publico\/Frame.aspx?x=\/Cabecalhos\/frame_ritcmd_04.htm\">Regulamento<\/a> (Resumo) do ITCMD (SEFAZ SC) disp\u00f5e.<\/p>\n\n\n\n<p>S\u00e3o isentos do pagamento do imposto (principais dispositivos apenas):<\/p>\n\n\n\n<p>I &#8211; o testamenteiro, com rela\u00e7\u00e3o ao pr\u00eamio institu\u00eddo pelo testador, desde que o valor deste <strong>n\u00e3o exceda \u00e0 vintena testament\u00e1ria<\/strong>;<\/p>\n\n\n\n<p>II &#8211; o benefici\u00e1rio de seguros de vida, pec\u00falio por morte e vencimentos, sal\u00e1rios, remunera\u00e7\u00f5es, honor\u00e1rios profissionais e demais vantagens pecuni\u00e1rias decorrentes de rela\u00e7\u00e3o de trabalho, inclusive benef\u00edcios da previd\u00eancia, oficial ou privada, n\u00e3o recebidos pelo \u201cde cujus\u201d;<\/p>\n\n\n\n<p>III &#8211; o herdeiro, o legat\u00e1rio, o donat\u00e1rio ou o cession\u00e1rio que houver sido aquinhoado com <strong>um \u00fanico bem im\u00f3vel<\/strong>, relativamente \u00e0 transmiss\u00e3o \u201ccausa mortis\u201d ou a doa\u00e7\u00e3o deste bem, desde que <strong>cumulativamente<\/strong>:<\/p>\n\n\n\n<p>a) o im\u00f3vel se destine \u00e0 <strong>moradia pr\u00f3pria<\/strong> do benefici\u00e1rio;<\/p>\n\n\n\n<p>b) o benefici\u00e1rio <strong>n\u00e3o possua qualquer outro bem im\u00f3vel<\/strong>; e<\/p>\n\n\n\n<p>c) o valor total do im\u00f3vel n\u00e3o seja superior a <strong>R$ 20.000,00<\/strong> (convenhamos que hoje em dia nem um lote vago \u00e9 vendido por um valor assim, n\u00e3o \u00e9 mesmo);<\/p>\n\n\n\n<p>IV &#8211; o herdeiro, o legat\u00e1rio, o donat\u00e1rio ou o cession\u00e1rio, quando o valor dos bens ou direitos recebidos n\u00e3o exceder ao equivalente a R$ 2.000,00.<\/p>\n\n\n\n<p>VIII \u2013 o benefici\u00e1rio de doa\u00e7\u00e3o de bem im\u00f3vel realizada pela Uni\u00e3o, Estado ou Munic\u00edpio, com vistas \u00e0 regulariza\u00e7\u00e3o fundi\u00e1ria, desde que integrante de fam\u00edlia com renda mensal de at\u00e9 5 (cinco) sal\u00e1rios-m\u00ednimos e que o im\u00f3vel seja destinado para uso pr\u00f3prio e de sua fam\u00edlia.<\/p>\n\n\n\n<p>Mister tamb\u00e9m saber que o ITCMD <strong>n\u00e3o incide<\/strong>:<\/p>\n\n\n\n<p>I &#8211; no caso de transmiss\u00e3o \u201ccausa mortis\u201d, sobre os frutos e rendimentos havidos ap\u00f3s o falecimento do \u201cde cujus\u201d; e<\/p>\n\n\n\n<p>II &#8211; na ren\u00fancia pura e simples \u00e0 sucess\u00e3o aberta.<\/p>\n\n\n\n<p><strong>Adendo:<\/strong> cuidado com as pegadinhas, Coruja. As 2 hip\u00f3teses acima n\u00e3o s\u00e3o de ISEN\u00c7\u00c3O nem IMUNIDADE, mas de n\u00e3o incid\u00eancia. Portanto, se ver alguma quest\u00e3o na prova pedindo para marcar as hip\u00f3teses de isen\u00e7\u00e3o do ITCMD e aparecer \u201cna ren\u00fancia pura e simples \u00e0 sucess\u00e3o aberta\u201d, marque esta como INCORRETA, uma vez que n\u00e3o \u00e9 isen\u00e7\u00e3o, mas N\u00c3O INCID\u00caNCIA.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-lancamento-do-itcmd\"><strong>Lan\u00e7amento do ITCMD<\/strong><\/h2>\n\n\n\n<p>O imposto \u00e9 lan\u00e7ado por Declara\u00e7\u00e3o. O cr\u00e9dito tribut\u00e1rio, por sua vez, poder\u00e1 ser parcelado em at\u00e9:<\/p>\n\n\n\n<p>I &#8211; 12 Presta\u00e7\u00f5es, quando apurado e declarado na DIEF-ITCMD pelo pr\u00f3prio sujeito passivo; ou<\/p>\n\n\n\n<p>II &#8211; 24 Presta\u00e7\u00f5es, quando exigido por notifica\u00e7\u00e3o fiscal.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-consideracoes-finais\"><strong>Considera\u00e7\u00f5es Finais<\/strong><\/h2>\n\n\n\n<p>Neste artigo estudamos a Lei 13.136\/04 e o Regulamento (RITCMD) de SC, com um resumo sobre o ITCMD para a SEFAZ SC.<\/p>\n\n\n\n<p>Vimos as diferen\u00e7as b\u00e1sicas entre o ITCMD, de compet\u00eancia estadual, e o ITBI, de compet\u00eancia municipal.<\/p>\n\n\n\n<p>Estudamos tamb\u00e9m a forma de c\u00e1lculo do ITCMD, que utiliza al\u00edquotas progressivas, em obedi\u00eancia ao princ\u00edpio da n\u00e3o cumulatividade e as hip\u00f3teses de isen\u00e7\u00e3o e n\u00e3o incid\u00eancia do tributo.<\/p>\n\n\n\n<p>Espero que tenham gostado do artigo e desejo uma excelente prova.<\/p>\n\n\n\n<p>Espero voc\u00ea aqui, na SEFAZ SC, em Chapec\u00f3, de prefer\u00eancia.<\/p>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-center\" id=\"h-cursos-e-assinaturas\">Cursos e Assinaturas<\/h2>\n\n\n\n<div class=\"container\" id=\"boxes\">\n  <div class=\"row\">\n\n    <div class=\"col-sm\">\n      <div class=\"banner-tribunal\" id=\"box-assinatura\">\n        <h3 class=\"titulo-assinatura\">Cursos para Carreiras Jur\u00eddicas<\/h3>\n        <p class=\"subtitulo-assinatura\">Conhe\u00e7a os cursos<\/p>\n        <div class=\"box-botao\">\n          <a class=\"btn-assinatura\" target=\"_blank\" href=\"https:\/\/www.estrategiaconcursos.com.br\/cursosPorConcurso\/assinaturas-carreira-juridica\/\" rel=\"noopener noreferrer\">Conhe\u00e7a mais<\/a>\n        <\/div>\n      <\/div>\n      <p class=\"texto-auxiliar\">Prepare-se com o melhor material e com quem mais aprova em Concursos P\u00fablicos em todo o pa\u00eds.<\/p>\n    <\/div>\n\n  <\/div>\n<\/div>\n\n\n\n<div class=\"container\" id=\"boxes\">\n  <div class=\"row\">\n\n    <div class=\"col-sm\">\n      <div class=\"banner-ecj\" id=\"box-assinatura\">\n        <h3 class=\"titulo-assinatura\">Assinatura Jur\u00eddica <\/h3>\n        <p class=\"subtitulo-assinatura\">Conhe\u00e7a os planos<\/p>\n        <div class=\"box-botao\">\n          <a class=\"btn-assinatura\" target=\"_blank\" href=\"https:\/\/www.estrategiaconcursos.com.br\/assinaturas-ecj\/\" role=\"button\" rel=\"noopener noreferrer\">Conhe\u00e7a mais<\/a>\n        <\/div>\n      <\/div>\n      <p class=\"texto-auxiliar\">Prepare-se com o melhor material e com quem mais aprova em Concursos P\u00fablicos em todo o pa\u00eds. \n<\/p>\n    <\/div>\n\n  <\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Veja as principais disposi\u00e7\u00f5es sobre a Lei 13.136\/04 e um resumo do ITCMD para a SEFAZ SC, concurso de Analista Tribut\u00e1rio 2021 Ol\u00e1, Coruja! Tudo certo por a\u00ed? J\u00e1 domina as disposi\u00e7\u00f5es principais sobre o ITCMD para a SEFAZ SC? O ITCMD, Imposto sobre Transmiss\u00e3o de Causa Mortis e Doa\u00e7\u00f5es, tamb\u00e9m \u00e9 conhecido pela sigla [&hellip;]<\/p>\n","protected":false},"author":1668,"featured_media":884499,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"post_tipo":"article","footnotes":""},"categories":[1983],"tags":[212391,220236],"tax_estado":[219987],"class_list":["post-884494","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-fiscal-estadual","tag-itcmd","tag-sefaz-sc-2","tax_estado-sc"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.2 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Resumo ITCMD para a SEFAZ SC \u2013 Analista Tribut\u00e1rio<\/title>\n<meta name=\"description\" content=\"Veja as principais disposi\u00e7\u00f5es sobre a Lei 13.136\/04 e um resumo do ITCMD para a SEFAZ SC, concurso de Analista Tribut\u00e1rio 2021\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-itcmd-sefaz-sc\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Resumo ITCMD para a SEFAZ SC \u2013 Analista Tribut\u00e1rio\" \/>\n<meta property=\"og:description\" content=\"Veja as principais disposi\u00e7\u00f5es sobre a Lei 13.136\/04 e um resumo do ITCMD para a SEFAZ SC, concurso de Analista Tribut\u00e1rio 2021\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-itcmd-sefaz-sc\/\" \/>\n<meta property=\"og:site_name\" content=\"Estrat\u00e9gia Concursos\" \/>\n<meta property=\"article:published_time\" content=\"2021-10-17T21:45:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-07-06T13:41:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/10\/14115351\/n_46517_e96d5e6d4b7386f182de7381a07cd06b__1_.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"870\" \/>\n\t<meta property=\"og:image:height\" content=\"450\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Leandro Ricardo Machado da Silveira\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:site\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Leandro Ricardo Machado da Silveira\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-itcmd-sefaz-sc\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-itcmd-sefaz-sc\/\"},\"author\":{\"name\":\"Leandro Ricardo Machado da Silveira\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/c666a44fbce7e2e70009a9c13549267a\"},\"headline\":\"Resumo ITCMD para a SEFAZ SC \u2013 Analista Tribut\u00e1rio\",\"datePublished\":\"2021-10-17T21:45:00+00:00\",\"dateModified\":\"2023-07-06T13:41:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-itcmd-sefaz-sc\/\"},\"wordCount\":1863,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-itcmd-sefaz-sc\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/10\/14115351\/n_46517_e96d5e6d4b7386f182de7381a07cd06b__1_.jpg\",\"keywords\":[\"itcmd\",\"SEFAZ SC\"],\"articleSection\":[\"Fiscal - Estadual (ICMS)\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-itcmd-sefaz-sc\/#respond\"]}],\"copyrightYear\":\"2021\",\"copyrightHolder\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-itcmd-sefaz-sc\/\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-itcmd-sefaz-sc\/\",\"name\":\"Resumo ITCMD para a SEFAZ SC \u2013 Analista Tribut\u00e1rio\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-itcmd-sefaz-sc\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-itcmd-sefaz-sc\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/10\/14115351\/n_46517_e96d5e6d4b7386f182de7381a07cd06b__1_.jpg\",\"datePublished\":\"2021-10-17T21:45:00+00:00\",\"dateModified\":\"2023-07-06T13:41:46+00:00\",\"description\":\"Veja as principais disposi\u00e7\u00f5es sobre a Lei 13.136\/04 e um resumo do ITCMD para a SEFAZ SC, concurso de Analista Tribut\u00e1rio 2021\",\"breadcrumb\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-itcmd-sefaz-sc\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-itcmd-sefaz-sc\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-itcmd-sefaz-sc\/#primaryimage\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/10\/14115351\/n_46517_e96d5e6d4b7386f182de7381a07cd06b__1_.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/10\/14115351\/n_46517_e96d5e6d4b7386f182de7381a07cd06b__1_.jpg\",\"width\":870,\"height\":450},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-itcmd-sefaz-sc\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Resumo ITCMD para a SEFAZ SC \u2013 Analista Tribut\u00e1rio\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"name\":\"Estrat\u00e9gia Concursos\",\"description\":\"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.\",\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\",\"name\":\"Estrat\u00e9gia Concursos\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"width\":230,\"height\":60,\"caption\":\"Estrat\u00e9gia Concursos\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/EstratConcursos\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/c666a44fbce7e2e70009a9c13549267a\",\"name\":\"Leandro Ricardo Machado da Silveira\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/6fb25994d16b9649838400aa459b16c1c83f558e0fd6ebebd16da0473908b291?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/6fb25994d16b9649838400aa459b16c1c83f558e0fd6ebebd16da0473908b291?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/6fb25994d16b9649838400aa459b16c1c83f558e0fd6ebebd16da0473908b291?s=96&d=mm&r=g\",\"caption\":\"Leandro Ricardo Machado da Silveira\"},\"description\":\"Engenheiro Aeron\u00e1utico, formado pela Universidade Federal de Uberl\u00e2ndia, possui MBA em Administra\u00e7\u00e3o e Finan\u00e7as Corporativas e aprovado nos concursos de Auditor Fiscal SEFAZ-SC e SEFAZ-GO.\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/leandro_vzthotmail-com\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Resumo ITCMD para a SEFAZ SC \u2013 Analista Tribut\u00e1rio","description":"Veja as principais disposi\u00e7\u00f5es sobre a Lei 13.136\/04 e um resumo do ITCMD para a SEFAZ SC, concurso de Analista Tribut\u00e1rio 2021","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-itcmd-sefaz-sc\/","og_locale":"pt_BR","og_type":"article","og_title":"Resumo ITCMD para a SEFAZ SC \u2013 Analista Tribut\u00e1rio","og_description":"Veja as principais disposi\u00e7\u00f5es sobre a Lei 13.136\/04 e um resumo do ITCMD para a SEFAZ SC, concurso de Analista Tribut\u00e1rio 2021","og_url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-itcmd-sefaz-sc\/","og_site_name":"Estrat\u00e9gia Concursos","article_published_time":"2021-10-17T21:45:00+00:00","article_modified_time":"2023-07-06T13:41:46+00:00","og_image":[{"width":870,"height":450,"url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/10\/14115351\/n_46517_e96d5e6d4b7386f182de7381a07cd06b__1_.jpg","type":"image\/jpeg"}],"author":"Leandro Ricardo Machado da Silveira","twitter_card":"summary_large_image","twitter_creator":"@EstratConcursos","twitter_site":"@EstratConcursos","twitter_misc":{"Escrito por":"Leandro Ricardo Machado da Silveira","Est. tempo de leitura":"8 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-itcmd-sefaz-sc\/#article","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-itcmd-sefaz-sc\/"},"author":{"name":"Leandro Ricardo Machado da Silveira","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/c666a44fbce7e2e70009a9c13549267a"},"headline":"Resumo ITCMD para a SEFAZ SC \u2013 Analista Tribut\u00e1rio","datePublished":"2021-10-17T21:45:00+00:00","dateModified":"2023-07-06T13:41:46+00:00","mainEntityOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-itcmd-sefaz-sc\/"},"wordCount":1863,"commentCount":0,"publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-itcmd-sefaz-sc\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/10\/14115351\/n_46517_e96d5e6d4b7386f182de7381a07cd06b__1_.jpg","keywords":["itcmd","SEFAZ SC"],"articleSection":["Fiscal - Estadual (ICMS)"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-itcmd-sefaz-sc\/#respond"]}],"copyrightYear":"2021","copyrightHolder":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-itcmd-sefaz-sc\/","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-itcmd-sefaz-sc\/","name":"Resumo ITCMD para a SEFAZ SC \u2013 Analista Tribut\u00e1rio","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-itcmd-sefaz-sc\/#primaryimage"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-itcmd-sefaz-sc\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/10\/14115351\/n_46517_e96d5e6d4b7386f182de7381a07cd06b__1_.jpg","datePublished":"2021-10-17T21:45:00+00:00","dateModified":"2023-07-06T13:41:46+00:00","description":"Veja as principais disposi\u00e7\u00f5es sobre a Lei 13.136\/04 e um resumo do ITCMD para a SEFAZ SC, concurso de Analista Tribut\u00e1rio 2021","breadcrumb":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-itcmd-sefaz-sc\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-itcmd-sefaz-sc\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-itcmd-sefaz-sc\/#primaryimage","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/10\/14115351\/n_46517_e96d5e6d4b7386f182de7381a07cd06b__1_.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/10\/14115351\/n_46517_e96d5e6d4b7386f182de7381a07cd06b__1_.jpg","width":870,"height":450},{"@type":"BreadcrumbList","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-itcmd-sefaz-sc\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.estrategiaconcursos.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Resumo ITCMD para a SEFAZ SC \u2013 Analista Tribut\u00e1rio"}]},{"@type":"WebSite","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","name":"Estrat\u00e9gia Concursos","description":"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.","publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization","name":"Estrat\u00e9gia Concursos","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","width":230,"height":60,"caption":"Estrat\u00e9gia Concursos"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/EstratConcursos"]},{"@type":"Person","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/c666a44fbce7e2e70009a9c13549267a","name":"Leandro Ricardo Machado da Silveira","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/6fb25994d16b9649838400aa459b16c1c83f558e0fd6ebebd16da0473908b291?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/6fb25994d16b9649838400aa459b16c1c83f558e0fd6ebebd16da0473908b291?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6fb25994d16b9649838400aa459b16c1c83f558e0fd6ebebd16da0473908b291?s=96&d=mm&r=g","caption":"Leandro Ricardo Machado da Silveira"},"description":"Engenheiro Aeron\u00e1utico, formado pela Universidade Federal de Uberl\u00e2ndia, possui MBA em Administra\u00e7\u00e3o e Finan\u00e7as Corporativas e aprovado nos concursos de Auditor Fiscal SEFAZ-SC e SEFAZ-GO.","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/leandro_vzthotmail-com\/"}]}},"_links":{"self":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/884494","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/users\/1668"}],"replies":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/comments?post=884494"}],"version-history":[{"count":4,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/884494\/revisions"}],"predecessor-version":[{"id":1244233,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/884494\/revisions\/1244233"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media\/884499"}],"wp:attachment":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media?parent=884494"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/categories?post=884494"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tags?post=884494"},{"taxonomy":"tax_estado","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tax_estado?post=884494"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}