{"id":882600,"date":"2021-10-12T11:57:00","date_gmt":"2021-10-12T14:57:00","guid":{"rendered":"https:\/\/blog-estrategia.mystagingwebsite.com\/blog\/?p=882600"},"modified":"2023-07-06T10:03:10","modified_gmt":"2023-07-06T13:03:10","slug":"resumo-contribuicao-melhoria-sefaz-sc","status":"publish","type":"post","link":"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-contribuicao-melhoria-sefaz-sc\/","title":{"rendered":"Resumo Contribui\u00e7\u00e3o de Melhoria SEFAZ SC"},"content":{"rendered":"\n<p class=\"has-medium-font-size wp-block-paragraph\">Veja as principais disposi\u00e7\u00f5es e um Resumo sobre a Contribui\u00e7\u00e3o de Melhoria para a SEFAZ SC \u2013 Concurso de Analista Tribut\u00e1rio<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"259\" height=\"194\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/10\/14115701\/download-6.jpg\" alt=\"Resumo Contribui\u00e7\u00e3o de Melhoria SEFAZ SC\" class=\"wp-image-884509\"\/><figcaption class=\"wp-element-caption\">Resumo Contribui\u00e7\u00e3o de Melhoria SEFAZ SC<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Ol\u00e1, Coruja. Tudo certo?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Imagino que esteja neste artigo, porque prestar\u00e1 o concurso da SEFAZ SC para Analista Tribut\u00e1rio, certo?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Como visto no edital, a<a href=\"http:\/\/legislacao.sef.sc.gov.br\/Consulta\/Views\/Publico\/Frame.aspx?x=\/html\/leis\/1983\/Lei_83_6323.htm\"> Lei n\u00b0 6.323, de 29 de dezembro de 1983<\/a> ser\u00e1 um dos t\u00f3picos a serem cobrados no certame. Por isso, realizei aqui, em primeira m\u00e3o, um Resumo sobre a Contribui\u00e7\u00e3o de Melhoria para a SEFAZ SC \u2013 Concurso de Analista Tribut\u00e1rio.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-quem-e-competente-para-instituir-contribuicao-de-melhoria\"><strong>Quem \u00e9 competente para instituir Contribui\u00e7\u00e3o de Melhoria?<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Afinal, Contribui\u00e7\u00e3o de Melhoria \u00e9 um tributo que est\u00e1 na compet\u00eancia de qual ente federativo?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Voc\u00ea deve estar pensando que se trata de um tributo estadual, acertei? Se pensou isso, enganou-se profundamente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De acordo com a Constitui\u00e7\u00e3o Federal, a Contribui\u00e7\u00e3o de Melhoria, decorrente de obra p\u00fablica, \u00e9 um tributo que pode ser institu\u00eddo pela Uni\u00e3o, pelos Estados, pelo Distrito Federal e pelos Munic\u00edpios.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-disposicoes-gerais-do-ctn\"><strong>Disposi\u00e7\u00f5es Gerais do CTN<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">N\u00e3o \u00e9 somente a Lei 6.323 que disp\u00f5e sobre as especificidades da Contribui\u00e7\u00e3o de Melhoria, mas tamb\u00e9m o C\u00f3digo Tribut\u00e1rio Nacional, com as disposi\u00e7\u00f5es gerais sobre o tema. Veja:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A Contribui\u00e7\u00e3o de Melhoria cobrada pela Uni\u00e3o, pelos Estados, pelo Distrito Federal ou pelos Munic\u00edpios, no \u00e2mbito de suas respectivas atribui\u00e7\u00f5es, \u00e9 institu\u00edda para fazer face ao <strong>custo de obras p\u00fablicas de que decorra valoriza\u00e7\u00e3o imobili\u00e1ria<\/strong>, tendo como limite total a despesa realizada e como limite individual o acr\u00e9scimo de valor que da obra resultar para cada im\u00f3vel beneficiado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Conclus\u00f5es Importantes:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00b7 &nbsp; &nbsp; &nbsp; &nbsp; Tem que haver obra p\u00fablica<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00b7 &nbsp; &nbsp; &nbsp; &nbsp; Tem que haver valoriza\u00e7\u00e3o imobili\u00e1ria<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00b7 &nbsp; &nbsp; &nbsp; &nbsp; Limite total: despesa da obra p\u00fablica rateada entre todos que tiveram seus im\u00f3veis valorizados em decorr\u00eancia da obra p\u00fablica<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00b7 &nbsp; &nbsp; &nbsp; &nbsp; Limite individual: valoriza\u00e7\u00e3o imobili\u00e1ria de cada contribuinte<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-resumo-contribuicao-de-melhoria-sefaz-sc-lei-6-323\"><strong>Resumo Contribui\u00e7\u00e3o de Melhoria SEFAZ SC &#8211; Lei 6.323<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">De acordo com a Lei Catarinense sobre a Contribui\u00e7\u00e3o de Melhoria, o lan\u00e7amento ser\u00e1 precedido de ato que conter\u00e1 os seguintes elementos:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">1. &nbsp; &nbsp; &nbsp; Memorial descritivo do projeto;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">2. &nbsp; &nbsp; &nbsp; Or\u00e7amento do custo da obra;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">3. &nbsp; &nbsp; &nbsp; Determina\u00e7\u00e3o da parcela do custo da obra a ser financiada pela contribui\u00e7\u00e3o;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">4. &nbsp; &nbsp; &nbsp; Delimita\u00e7\u00e3o da zona beneficiada; e<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">5. &nbsp; &nbsp; &nbsp; Determina\u00e7\u00e3o do fator de absor\u00e7\u00e3o do benef\u00edcio para toda a zona ou cada uma das \u00e1reas diferenciadas, nela contidas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Leandro, mas eu preciso decorar isso? Parece excesso de decoreba, n\u00e3o acha? Concordo em partes com voc\u00ea! Se estes 5 itens estivessem do meio pro final da Lei, acharia dispens\u00e1vel a sua memoriza\u00e7\u00e3o. Contudo, trata-se do 2\u00ba artigo, Coruja! Portanto, acho que \u00e9 v\u00e1lido decorar.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Foco, for\u00e7a e f\u00e9!<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Adendo:<\/strong> lembra-se do limite total? Despesa da obra p\u00fablica? Pois bem, ser\u00e3o computados na apura\u00e7\u00e3o dos custos as despesas relativas a estudos, administra\u00e7\u00e3o e encargos de financiamentos (juros).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Outra pergunta interessante: ser\u00e1 que os propriet\u00e1rios dos im\u00f3veis valorizados t\u00eam direito a contestar o lan\u00e7amento da Contribui\u00e7\u00e3o de Melhoria? Certamente que sim! Veja:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Poder\u00e3o os interessados ou entidade que os represente impugnar qualquer dos elementos referidos no artigo anterior, no prazo m\u00e1ximo de 30 (trinta) dias a contar da data da \u00faltima publica\u00e7\u00e3o do lan\u00e7amento.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al\u00e9m disso, a impugna\u00e7\u00e3o <strong>suspender\u00e1<\/strong> os efeitos do lan\u00e7amento e a decis\u00e3o sobre ela, o manter\u00e1 ou o cancelar\u00e1.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Na \u00faltima hip\u00f3tese, o cancelamento do lan\u00e7amento <strong>n\u00e3o elide a efetiva\u00e7\u00e3o de novo<\/strong>, em substitui\u00e7\u00e3o ao anterior, com as corre\u00e7\u00f5es impostas pela impugna\u00e7\u00e3o.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-hipoteses-de-incidencia\"><strong>Hip\u00f3teses de Incid\u00eancia<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">De acordo com o (Resumo) da Contribui\u00e7\u00e3o de Melhoria SEFAZ SC, ser\u00e1 exigida a Contribui\u00e7\u00e3o de Melhoria pela execu\u00e7\u00e3o de qualquer das obras a seguir relacionadas:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">1. &nbsp; &nbsp; &nbsp; Abertura e pavimenta\u00e7\u00e3o de vias p\u00fablicas;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">2. &nbsp; &nbsp; &nbsp; Constru\u00e7\u00e3o de estradas de ferro, constru\u00e7\u00e3o, pavimenta\u00e7\u00e3o e melhoramento de estradas de rodagem.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Todavia, o Decreto Lei 195 prev\u00ea mais hip\u00f3teses de incid\u00eancia que somente estas duas:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00b7 &nbsp; &nbsp; &nbsp; &nbsp; Abertura, alargamento, pavimenta\u00e7\u00e3o, ilumina\u00e7\u00e3o, arboriza\u00e7\u00e3o, esgotos pluviais e outros melhoramentos de pra\u00e7as e vias p\u00fablicas;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00b7 &nbsp; &nbsp; &nbsp; &nbsp; Constru\u00e7\u00e3o e amplia\u00e7\u00e3o de parques, campos de desportos, pontes, t\u00faneis e viadutos;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00b7 &nbsp; &nbsp; &nbsp; &nbsp; Constru\u00e7\u00e3o ou amplia\u00e7\u00e3o de sistemas de tr\u00e2nsito r\u00e1pido inclusive todas as obras e edifica\u00e7\u00f5es necess\u00e1rias ao funcionamento do sistema;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00b7 &nbsp; &nbsp; &nbsp; &nbsp; Servi\u00e7os e obras de abastecimento de \u00e1gua pot\u00e1vel, esgotos, instala\u00e7\u00f5es de redes el\u00e9tricas, telef\u00f4nicas, transportes e comunica\u00e7\u00f5es em geral ou de suprimento de g\u00e1s, funiculares, ascensores e instala\u00e7\u00f5es de comodidade p\u00fablica;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00b7 &nbsp; &nbsp; &nbsp; &nbsp; Prote\u00e7\u00e3o contra secas, inunda\u00e7\u00f5es, eros\u00e3o, ressacas, e de saneamento de drenagem em geral, diques, cais, desobstru\u00e7\u00e3o de barras, portos e canais, retifica\u00e7\u00e3o e regulariza\u00e7\u00e3o de cursos d\u2019\u00e1gua e irriga\u00e7\u00e3o;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00b7 &nbsp; &nbsp; &nbsp; &nbsp; Constru\u00e7\u00e3o de estradas de ferro e constru\u00e7\u00e3o, pavimenta\u00e7\u00e3o e melhoramento de estradas de rodagem;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00b7 &nbsp; &nbsp; &nbsp; &nbsp; Constru\u00e7\u00e3o de aer\u00f3dromos e aeroportos e seus acessos;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00b7 &nbsp; &nbsp; &nbsp; &nbsp; Aterros e realiza\u00e7\u00f5es de embelezamento em geral, inclusive desapropria\u00e7\u00f5es em desenvolvimento de plano de aspecto paisag\u00edstico.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fique ligado no dispositivo da quest\u00e3o! Se o enunciado se refere \u00e0 Lei ou ao Decreto Lei.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Par\u00e1grafo \u00fanico. Reputa-se feita pelo Estado, qualquer obra realizada por <strong>autarquia ou sociedade de economia mista<\/strong> institu\u00edda por lei estadual, ou para a qual, o Estado tenha concorrido com a <strong>metade ou mais dos gastos<\/strong>, bem como as realizadas em <strong>conv\u00eanio<\/strong> com quaisquer entidades p\u00fablicas. (Importante)<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-sujeitos-passivos\"><strong>Sujeitos Passivos<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Estrategista, ISSO DAQUI SEUS CONCORRENTES V\u00c3O ERRAR! ANOTE!<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O que a gente aprende? Que o CONTRIBUINTE da Contribui\u00e7\u00e3o de melhoria \u00e9 o PROPRIET\u00c1RIO.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Masssss&#8230;.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Segundo a Lei 6.323 do Estado de SC, \u00e9 <strong>RESPONS\u00c1VEL<\/strong> pelo pagamento da Contribui\u00e7\u00e3o de Melhoria, o PROPRIET\u00c1RIO do im\u00f3vel, ao tempo do respectivo lan\u00e7amento.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Portanto, se ver em sua prova: \u201csegundo a Lei 6.323 o propriet\u00e1rio do im\u00f3vel \u00e9 RESPONS\u00c1VEL pelo pagamento da Contribui\u00e7\u00e3o de Melhoria\u201d marque certo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al\u00e9m disso, o Decreto Lei 195 de SC disp\u00f5e que:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00b7 &nbsp; &nbsp; &nbsp; &nbsp; No caso de enfiteuse, responde pela Contribui\u00e7\u00e3o de Melhoria o enfiteuta.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00b7 &nbsp; &nbsp; &nbsp; &nbsp; No im\u00f3vel locado \u00e9 l\u00edcito ao locador exigir aumento de aluguel correspondente a 10% (dez por cento) ao ano da Contribui\u00e7\u00e3o de Melhoria efetivamente paga.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00b7 &nbsp; &nbsp; &nbsp; &nbsp; \u00c9 <strong>nula<\/strong> a cl\u00e1usula do contrato de loca\u00e7\u00e3o que atribui ao locat\u00e1rio o pagamento, no todo ou em parte, da Contribui\u00e7\u00e3o de Melhoria lan\u00e7ada sobre o im\u00f3vel.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-hipoteses-de-isencao\"><strong>Hip\u00f3teses de Isen\u00e7\u00e3o<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Segundo a Lei, s\u00e3o isentos da Contribui\u00e7\u00e3o de Melhoria:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;I.&nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; O im\u00f3vel, que na distribui\u00e7\u00e3o &#8220;pro rata\u201d do custo total da obra ou melhoramento, estaria sujeito ao pagamento da import\u00e2ncia ig<strong>ual ou inferior \u00e0 metade do sal\u00e1rio m\u00ednimo <\/strong>vigente no Estado, por ocasi\u00e3o do lan\u00e7amento individual;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;&nbsp; II.&nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; O im\u00f3vel <strong>rural<\/strong> da \u00e1rea inferior a <strong>25 hectares<\/strong>, quando <strong>propriedade \u00fanica<\/strong>, e <strong>explorada <\/strong>pelo propriet\u00e1rio e sua fam\u00edlia, em atividade agr\u00edcolas ou pastoris;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">III.&nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; Os tempos de qualquer culto, no que se refere \u00e0 parte fronteiri\u00e7a da constru\u00e7\u00e3o em rela\u00e7\u00e3o a logradouro p\u00fablico, numa extens\u00e3o de at\u00e9 50 (cinquenta) metros de testada, inclusive quando se tratar da \u00e1rea de influ\u00eancia;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">IV.&nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; O im\u00f3vel pertencente ao munic\u00edpio, <strong>que conceder tratamento rec\u00edproco<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;&nbsp; V.&nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; As entidades beneficentes, culturais e esportivas que:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">a. &nbsp; &nbsp; &nbsp; N\u00e3o distribu\u00edrem qualquer parcela de seu patrim\u00f4nio ou de suas rendas, a qualquer t\u00edtulo;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">b.&nbsp; &nbsp; &nbsp; &nbsp;Aplicarem integralmente, no pa\u00eds, os seus recursos na manuten\u00e7\u00e3o dos seus objetivos institucionais;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">c. &nbsp; &nbsp; &nbsp; Mantenham escritura\u00e7\u00e3o de suas receitas e despesas em livros revestidos de formalidades capazes de assegurar sua exatid\u00e3o.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-pagamento\"><strong>Pagamento<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">O pagamento da Contribui\u00e7\u00e3o de Melhoria ser\u00e1 feito:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">a)&nbsp; &nbsp; &nbsp; No prazo de 30 (trinta) dias, contados da data em que o contribuinte receber o aviso de lan\u00e7amento, desde que sua renda mensal bruta seja equivalente ao triplo da quantia lan\u00e7ada, ocasi\u00e3o em que gozar\u00e1 de bonifica\u00e7\u00e3o de 10% do total devido.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">b)&nbsp; &nbsp; &nbsp; At\u00e9 12 (doze) meses, acrescidos dos juros oficiais mensais, quando a renda mensal bruta do contribuinte atingir o dobro da quantia lan\u00e7ada.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">c) &nbsp; &nbsp; &nbsp; At\u00e9 24 (vinte e quatro) meses, acrescido dos juros oficiais mensais, quando a renda mensal bruta do contribuinte for igual ou superior ao total da quantia lan\u00e7ada.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">d)&nbsp; &nbsp; &nbsp; At\u00e9 36 (trinta e seis) meses, acrescido dos juros oficiais mensais, quando a renda mensal bruta do contribuinte for inferior ao total da quantia lan\u00e7ada.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-curiosidade-contribuicao-de-melhoria-e-muito-cobrada-no-brasil\"><strong>Curiosidade: Contribui\u00e7\u00e3o de Melhoria \u00e9 muito cobrada no Brasil?<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Com base no que estudamos neste artigo, parece um tributo um tanto quanto justo, n\u00e3o \u00e9 mesmo?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Se o Governo realizou uma obra p\u00fablica que valoriza um im\u00f3vel de outrem, nada mais justo que este recompensar esse \u201cenriquecimento\u201d para fazer jus \u00e0s despesas da obra.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Contudo, por que nunca ouvimos falar da cobran\u00e7a da Contribui\u00e7\u00e3o de Melhoria na pr\u00e1tica?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Em um primeiro momento, pode parecer dif\u00edcil mensurar quanto de fato um im\u00f3vel se valorizou apenas pelo fato da obra p\u00fablica. Seria nada mais nada menos que um chute, n\u00e3o \u00e9 verdade? Mas, por outro lado, \u00e9 plenamente poss\u00edvel a aferi\u00e7\u00e3o.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Uma poss\u00edvel justificativa seria que nossos pol\u00edticos n\u00e3o est\u00e3o interessados em serem fiscalizados.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Est\u00e1 louco, Leandro? O que uma coisa tem a ver com outra? Pense bem&#8230;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Qual o limite da Contribui\u00e7\u00e3o de Melhoria: custo da obra, certo?!<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Digamos que um determinado hospital tenha sido constru\u00eddo por R$ 30 milh\u00f5es de reais e que haja superfaturamento na obra. E que mesmo assim o Chefe do Executivo resolva cobrar dos propriet\u00e1rios de im\u00f3veis pr\u00f3ximos o referido tributo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ser\u00e1 que estes propriet\u00e1rios n\u00e3o iriam analisar com calma todos os custos da obra p\u00fablica e questionar alguns valores?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Reflita sobre isso e tire suas pr\u00f3prias conclus\u00f5es!<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Um forte abra\u00e7o<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Leandro Silveira<\/p>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-center\" id=\"h-cursos-e-assinaturas\">Cursos e Assinaturas<\/h2>\n\n\n\n<div class=\"container\" id=\"boxes\">\n  <div class=\"row\">\n\n    <div class=\"col-sm\">\n      <div class=\"banner-tribunal\" id=\"box-assinatura\">\n        <h3 class=\"titulo-assinatura\">Cursos para Carreiras Jur\u00eddicas<\/h3>\n        <p class=\"subtitulo-assinatura\">Conhe\u00e7a os cursos<\/p>\n        <div class=\"box-botao\">\n          <a class=\"btn-assinatura\" target=\"_blank\" href=\"https:\/\/www.estrategiaconcursos.com.br\/cursosPorConcurso\/assinaturas-carreira-juridica\/\" rel=\"noopener noreferrer\">Conhe\u00e7a mais<\/a>\n        <\/div>\n      <\/div>\n      <p class=\"texto-auxiliar\">Prepare-se com o melhor material e com quem mais aprova em Concursos P\u00fablicos em todo o pa\u00eds.<\/p>\n    <\/div>\n\n  <\/div>\n<\/div>\n\n\n\n<div class=\"container\" id=\"boxes\">\n  <div class=\"row\">\n\n    <div class=\"col-sm\">\n      <div class=\"banner-ecj\" id=\"box-assinatura\">\n        <h3 class=\"titulo-assinatura\">Assinatura Jur\u00eddica <\/h3>\n        <p class=\"subtitulo-assinatura\">Conhe\u00e7a os planos<\/p>\n        <div class=\"box-botao\">\n          <a class=\"btn-assinatura\" target=\"_blank\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/assinaturas-ecj\/\" role=\"button\" rel=\"noopener noreferrer\">Conhe\u00e7a mais<\/a>\n        <\/div>\n      <\/div>\n      <p class=\"texto-auxiliar\">Prepare-se com o melhor material e com quem mais aprova em Concursos P\u00fablicos em todo o pa\u00eds. \n<\/p>\n    <\/div>\n\n  <\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Veja as principais disposi\u00e7\u00f5es e um Resumo sobre a Contribui\u00e7\u00e3o de Melhoria para a SEFAZ SC \u2013 Concurso de Analista Tribut\u00e1rio Ol\u00e1, Coruja. Tudo certo? Imagino que esteja neste artigo, porque prestar\u00e1 o concurso da SEFAZ SC para Analista Tribut\u00e1rio, certo? Como visto no edital, a Lei n\u00b0 6.323, de 29 de dezembro de 1983 [&hellip;]<\/p>\n","protected":false},"author":1668,"featured_media":884510,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"post_tipo":"article","footnotes":""},"categories":[1983],"tags":[220094,220236],"tax_estado":[219987],"class_list":["post-882600","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-fiscal-estadual","tag-contribuicao-de-melhoria","tag-sefaz-sc-2","tax_estado-sc"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.1 (Yoast SEO v28.1) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Resumo Contribui\u00e7\u00e3o de Melhoria SEFAZ SC<\/title>\n<meta name=\"description\" content=\"Veja as principais disposi\u00e7\u00f5es e um Resumo sobre a Contribui\u00e7\u00e3o de Melhoria para a SEFAZ SC \u2013 Concurso de Analista Tribut\u00e1rio\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-contribuicao-melhoria-sefaz-sc\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Resumo Contribui\u00e7\u00e3o de Melhoria SEFAZ SC\" \/>\n<meta property=\"og:description\" content=\"Veja as principais disposi\u00e7\u00f5es e um Resumo sobre a Contribui\u00e7\u00e3o de Melhoria para a SEFAZ SC \u2013 Concurso de Analista Tribut\u00e1rio\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-contribuicao-melhoria-sefaz-sc\/\" \/>\n<meta property=\"og:site_name\" content=\"Estrat\u00e9gia Concursos\" \/>\n<meta property=\"article:published_time\" content=\"2021-10-12T14:57:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-07-06T13:03:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/10\/14115729\/download-6-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"259\" \/>\n\t<meta property=\"og:image:height\" content=\"194\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Leandro Ricardo Machado da Silveira\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:site\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Leandro Ricardo Machado da Silveira\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/resumo-contribuicao-melhoria-sefaz-sc\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/resumo-contribuicao-melhoria-sefaz-sc\\\/\"},\"author\":{\"name\":\"Leandro Ricardo Machado da Silveira\",\"@id\":\"https:\\\/\\\/blog-estrategia.mystagingwebsite.com\\\/#\\\/schema\\\/person\\\/c666a44fbce7e2e70009a9c13549267a\"},\"headline\":\"Resumo Contribui\u00e7\u00e3o de Melhoria SEFAZ SC\",\"datePublished\":\"2021-10-12T14:57:00+00:00\",\"dateModified\":\"2023-07-06T13:03:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/resumo-contribuicao-melhoria-sefaz-sc\\\/\"},\"wordCount\":1892,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/blog-estrategia.mystagingwebsite.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/resumo-contribuicao-melhoria-sefaz-sc\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dhg1h5j42swfq.cloudfront.net\\\/2021\\\/10\\\/14115729\\\/download-6-1.jpg\",\"keywords\":[\"contribui\u00e7\u00e3o de melhoria\",\"SEFAZ SC\"],\"articleSection\":[\"Fiscal - Estadual (ICMS)\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/resumo-contribuicao-melhoria-sefaz-sc\\\/#respond\"]}],\"copyrightYear\":\"2021\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/resumo-contribuicao-melhoria-sefaz-sc\\\/\",\"url\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/resumo-contribuicao-melhoria-sefaz-sc\\\/\",\"name\":\"Resumo Contribui\u00e7\u00e3o de Melhoria SEFAZ SC\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog-estrategia.mystagingwebsite.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/resumo-contribuicao-melhoria-sefaz-sc\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/resumo-contribuicao-melhoria-sefaz-sc\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dhg1h5j42swfq.cloudfront.net\\\/2021\\\/10\\\/14115729\\\/download-6-1.jpg\",\"datePublished\":\"2021-10-12T14:57:00+00:00\",\"dateModified\":\"2023-07-06T13:03:10+00:00\",\"description\":\"Veja as principais disposi\u00e7\u00f5es e um Resumo sobre a Contribui\u00e7\u00e3o de Melhoria para a SEFAZ SC \u2013 Concurso de Analista Tribut\u00e1rio\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/resumo-contribuicao-melhoria-sefaz-sc\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/resumo-contribuicao-melhoria-sefaz-sc\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/resumo-contribuicao-melhoria-sefaz-sc\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dhg1h5j42swfq.cloudfront.net\\\/2021\\\/10\\\/14115729\\\/download-6-1.jpg\",\"contentUrl\":\"https:\\\/\\\/dhg1h5j42swfq.cloudfront.net\\\/2021\\\/10\\\/14115729\\\/download-6-1.jpg\",\"width\":259,\"height\":194},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/resumo-contribuicao-melhoria-sefaz-sc\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/blog-estrategia.mystagingwebsite.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Resumo Contribui\u00e7\u00e3o de Melhoria SEFAZ SC\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blog-estrategia.mystagingwebsite.com\\\/#website\",\"url\":\"https:\\\/\\\/blog-estrategia.mystagingwebsite.com\\\/\",\"name\":\"Estrat\u00e9gia Concursos\",\"description\":\"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.\",\"publisher\":{\"@id\":\"https:\\\/\\\/blog-estrategia.mystagingwebsite.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blog-estrategia.mystagingwebsite.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/blog-estrategia.mystagingwebsite.com\\\/#organization\",\"name\":\"Estrat\u00e9gia Concursos\",\"url\":\"https:\\\/\\\/blog-estrategia.mystagingwebsite.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/blog-estrategia.mystagingwebsite.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dhg1h5j42swfq.cloudfront.net\\\/2025\\\/06\\\/03203428\\\/logo_concursos-1.jpg\",\"contentUrl\":\"https:\\\/\\\/dhg1h5j42swfq.cloudfront.net\\\/2025\\\/06\\\/03203428\\\/logo_concursos-1.jpg\",\"width\":230,\"height\":60,\"caption\":\"Estrat\u00e9gia Concursos\"},\"image\":{\"@id\":\"https:\\\/\\\/blog-estrategia.mystagingwebsite.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/EstratConcursos\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/blog-estrategia.mystagingwebsite.com\\\/#\\\/schema\\\/person\\\/c666a44fbce7e2e70009a9c13549267a\",\"name\":\"Leandro Ricardo Machado da Silveira\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6fb25994d16b9649838400aa459b16c1c83f558e0fd6ebebd16da0473908b291?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6fb25994d16b9649838400aa459b16c1c83f558e0fd6ebebd16da0473908b291?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6fb25994d16b9649838400aa459b16c1c83f558e0fd6ebebd16da0473908b291?s=96&d=mm&r=g\",\"caption\":\"Leandro Ricardo Machado da Silveira\"},\"description\":\"Engenheiro Aeron\u00e1utico, formado pela Universidade Federal de Uberl\u00e2ndia, possui MBA em Administra\u00e7\u00e3o e Finan\u00e7as Corporativas e aprovado nos concursos de Auditor Fiscal SEFAZ-SC e SEFAZ-GO.\",\"url\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/author\\\/leandro_vzthotmail-com\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Resumo Contribui\u00e7\u00e3o de Melhoria SEFAZ SC","description":"Veja as principais disposi\u00e7\u00f5es e um Resumo sobre a Contribui\u00e7\u00e3o de Melhoria para a SEFAZ SC \u2013 Concurso de Analista Tribut\u00e1rio","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-contribuicao-melhoria-sefaz-sc\/","og_locale":"pt_BR","og_type":"article","og_title":"Resumo Contribui\u00e7\u00e3o de Melhoria SEFAZ SC","og_description":"Veja as principais disposi\u00e7\u00f5es e um Resumo sobre a Contribui\u00e7\u00e3o de Melhoria para a SEFAZ SC \u2013 Concurso de Analista Tribut\u00e1rio","og_url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-contribuicao-melhoria-sefaz-sc\/","og_site_name":"Estrat\u00e9gia Concursos","article_published_time":"2021-10-12T14:57:00+00:00","article_modified_time":"2023-07-06T13:03:10+00:00","og_image":[{"width":259,"height":194,"url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/10\/14115729\/download-6-1.jpg","type":"image\/jpeg"}],"author":"Leandro Ricardo Machado da Silveira","twitter_card":"summary_large_image","twitter_creator":"@EstratConcursos","twitter_site":"@EstratConcursos","twitter_misc":{"Escrito por":"Leandro Ricardo Machado da Silveira","Est. tempo de leitura":"8 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-contribuicao-melhoria-sefaz-sc\/#article","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-contribuicao-melhoria-sefaz-sc\/"},"author":{"name":"Leandro Ricardo Machado da Silveira","@id":"https:\/\/blog-estrategia.mystagingwebsite.com\/#\/schema\/person\/c666a44fbce7e2e70009a9c13549267a"},"headline":"Resumo Contribui\u00e7\u00e3o de Melhoria SEFAZ SC","datePublished":"2021-10-12T14:57:00+00:00","dateModified":"2023-07-06T13:03:10+00:00","mainEntityOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-contribuicao-melhoria-sefaz-sc\/"},"wordCount":1892,"commentCount":0,"publisher":{"@id":"https:\/\/blog-estrategia.mystagingwebsite.com\/#organization"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-contribuicao-melhoria-sefaz-sc\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/10\/14115729\/download-6-1.jpg","keywords":["contribui\u00e7\u00e3o de melhoria","SEFAZ SC"],"articleSection":["Fiscal - Estadual (ICMS)"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-contribuicao-melhoria-sefaz-sc\/#respond"]}],"copyrightYear":"2021","copyrightHolder":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-contribuicao-melhoria-sefaz-sc\/","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-contribuicao-melhoria-sefaz-sc\/","name":"Resumo Contribui\u00e7\u00e3o de Melhoria SEFAZ SC","isPartOf":{"@id":"https:\/\/blog-estrategia.mystagingwebsite.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-contribuicao-melhoria-sefaz-sc\/#primaryimage"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-contribuicao-melhoria-sefaz-sc\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/10\/14115729\/download-6-1.jpg","datePublished":"2021-10-12T14:57:00+00:00","dateModified":"2023-07-06T13:03:10+00:00","description":"Veja as principais disposi\u00e7\u00f5es e um Resumo sobre a Contribui\u00e7\u00e3o de Melhoria para a SEFAZ SC \u2013 Concurso de Analista Tribut\u00e1rio","breadcrumb":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-contribuicao-melhoria-sefaz-sc\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-contribuicao-melhoria-sefaz-sc\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-contribuicao-melhoria-sefaz-sc\/#primaryimage","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/10\/14115729\/download-6-1.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/10\/14115729\/download-6-1.jpg","width":259,"height":194},{"@type":"BreadcrumbList","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-contribuicao-melhoria-sefaz-sc\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/blog-estrategia.mystagingwebsite.com\/"},{"@type":"ListItem","position":2,"name":"Resumo Contribui\u00e7\u00e3o de Melhoria SEFAZ SC"}]},{"@type":"WebSite","@id":"https:\/\/blog-estrategia.mystagingwebsite.com\/#website","url":"https:\/\/blog-estrategia.mystagingwebsite.com\/","name":"Estrat\u00e9gia Concursos","description":"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.","publisher":{"@id":"https:\/\/blog-estrategia.mystagingwebsite.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blog-estrategia.mystagingwebsite.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/blog-estrategia.mystagingwebsite.com\/#organization","name":"Estrat\u00e9gia Concursos","url":"https:\/\/blog-estrategia.mystagingwebsite.com\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/blog-estrategia.mystagingwebsite.com\/#\/schema\/logo\/image\/","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","width":230,"height":60,"caption":"Estrat\u00e9gia Concursos"},"image":{"@id":"https:\/\/blog-estrategia.mystagingwebsite.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/EstratConcursos"]},{"@type":"Person","@id":"https:\/\/blog-estrategia.mystagingwebsite.com\/#\/schema\/person\/c666a44fbce7e2e70009a9c13549267a","name":"Leandro Ricardo Machado da Silveira","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/6fb25994d16b9649838400aa459b16c1c83f558e0fd6ebebd16da0473908b291?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/6fb25994d16b9649838400aa459b16c1c83f558e0fd6ebebd16da0473908b291?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6fb25994d16b9649838400aa459b16c1c83f558e0fd6ebebd16da0473908b291?s=96&d=mm&r=g","caption":"Leandro Ricardo Machado da Silveira"},"description":"Engenheiro Aeron\u00e1utico, formado pela Universidade Federal de Uberl\u00e2ndia, possui MBA em Administra\u00e7\u00e3o e Finan\u00e7as Corporativas e aprovado nos concursos de Auditor Fiscal SEFAZ-SC e SEFAZ-GO.","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/leandro_vzthotmail-com\/"}]}},"_links":{"self":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/882600","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/users\/1668"}],"replies":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/comments?post=882600"}],"version-history":[{"count":0,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/882600\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media\/884510"}],"wp:attachment":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media?parent=882600"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/categories?post=882600"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tags?post=882600"},{"taxonomy":"tax_estado","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tax_estado?post=882600"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}