{"id":879436,"date":"2021-11-29T00:00:00","date_gmt":"2021-11-29T03:00:00","guid":{"rendered":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?p=879436"},"modified":"2021-11-30T12:04:03","modified_gmt":"2021-11-30T15:04:03","slug":"edital-ufc","status":"publish","type":"post","link":"https:\/\/www.estrategiaconcursos.com.br\/blog\/edital-ufc\/","title":{"rendered":"Edital UFC: inscri\u00e7\u00f5es prorrogadas! Prova em 30\/01"},"content":{"rendered":"\n<p><strong>Foram prorrogadas at\u00e9 o dia 5 de dezembro as inscri\u00e7\u00f5es do edital UFC.<\/strong> As <strong>provas<\/strong> ser\u00e3o aplicadas em\u00a0<strong>30 de janeiro de 2022<\/strong>. <strong>S\u00e3o ofertadas 81 vagas, sendo 42\u00a0para fun\u00e7\u00f5es de n\u00edvel m\u00e9dio\/t\u00e9cnico e 39 para superior.<\/strong>  <\/p>\n\n\n\n<p>A <strong>banca respons\u00e1vel pela sele\u00e7\u00e3o da Universidade Federal do Cear\u00e1 \u00e9 a&nbsp;Funda\u00e7\u00e3o Cetrede<\/strong>. Os candidatos aprovados no concurso ser\u00e3o lotados nos Campi da UFC, em Fortaleza, Crate\u00fas, Itapaj\u00e9, Russas e Sobral, respeitada a ordem de classifica\u00e7\u00e3o.<\/p>\n\n\n\n<ul id=\"block-ffde6a9e-f0a0-49d4-b1e5-b0efa00ba9c1\" class=\"has-very-light-gray-to-cyan-bluish-gray-gradient-background has-background wp-block-list\"><li><strong>UFC<\/strong> \u2013&nbsp;<strong>T\u00e9cnico Administrativo em Educa\u00e7\u00e3o<\/strong><\/li><li><strong>Status:<\/strong>&nbsp;inscri\u00e7\u00f5es prorrogadas<\/li><li><strong>Banca: <\/strong>Funda\u00e7\u00e3o Cetrede<\/li><li><strong>Vagas: <\/strong>81<\/li><li><strong>Sal\u00e1rio inicial:<\/strong> R$ 2.446,96 a R$ 4.180,66 <\/li><li><strong>Edital:<\/strong>&nbsp;<a href=\"https:\/\/www.in.gov.br\/en\/web\/dou\/-\/edital-n-1-de-6-de-outubro-de-2021-351254381\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">Edital-UFC 2021<\/a><\/li><\/ul>\n\n\n\n<p><strong>O edital do concurso UFC <\/strong>sofreu<strong> <\/strong>uma pequena <strong>retifica\u00e7\u00e3o<\/strong> divulgada no Di\u00e1rio Oficial da Uni\u00e3o de 18 de novembro de 2021. De acordo com a publica\u00e7\u00e3o, os subitens 12.1, 1.3.15 e 3.2.3 do Anexo I foram retificados ap\u00f3s prazo de impugna\u00e7\u00e3o do edital em substitui\u00e7\u00e3o ao disposto na reda\u00e7\u00e3o dada pelo edital 03\/2021 de 27 de outubro.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-principais-datas-do-edital-ufc\">Principais datas do edital&nbsp;UFC<\/h2>\n\n\n\n<p class=\"has-background\" style=\"background-color:#d4e1ec\"><strong><\/strong><strong>Inscri\u00e7\u00f5es<\/strong>: 05\/11 a 05\/12\/2021<br \/><strong>Isen\u00e7\u00e3o da taxa<\/strong>:&nbsp;<s>05 a 10\/11\/2021<\/s><br \/><strong>Pagamento da taxa:<\/strong> at\u00e9 06\/12\/2021<br \/><strong>Prova<\/strong>: 30\/01\/2022 <\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"retifica\u00e7\u00e3o\">Retifica\u00e7\u00e3o <\/h3>\n\n\n\n<p>A seguir, veja na \u00edntegra o que saiu e o que mudou no edital do concurso UFC:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>1. O subitem 7.1.1.2.1 do Edital n\u00ba 1 do concurso UFC, de 06 de Outubro de 2021 passa a vigorar com a seguinte reda\u00e7\u00e3o:<ul><li>7.1.1.2.1. comprova\u00e7\u00e3o da condi\u00e7\u00e3o de doador, por meio da declara\u00e7\u00e3o expedida por Hemocentro ou pelo aplicativo do Registro Nacional de Doadores Volunt\u00e1rios de Medula \u00d3ssea (REDOME), indicando o c\u00f3digo de doador (DMR) e o c\u00f3digo de valida\u00e7\u00e3o da declara\u00e7\u00e3o (c\u00f3digo num\u00e9rico presente abaixo da declara\u00e7\u00e3o).<\/li><\/ul><\/li><li>2. O subitem 7.1.1.2.2 do Edital n\u00ba 1, de 06 de Outubro de 2021 fica exclu\u00eddo.<\/li><li>3. O subitem 7.1.2. do Edital n\u00ba 1, de 06 de Outubro de 2021 passa a vigorar com a seguinte reda\u00e7\u00e3o:<ul><li>7.1.2. Em caso de 2 (duas) ou mais solicita\u00e7\u00f5es de isen\u00e7\u00e3o de um mesmo candidato, para cargos do mesmo N\u00edvel (M\u00e9dio\/T\u00e9cnico ou Superior), ser\u00e1 considerada aquela efetuada com data e hor\u00e1rio mais recente, sendo as demais canceladas.<\/li><\/ul><\/li><li>4. O subitem 11.2 do Edital n\u00ba 1, de 06 de Outubro de 2021, passa a vigorar com a seguinte reda\u00e7\u00e3o:<ul><li>11.2. Ter nacionalidade brasileira (nato ou naturalizado), ou ainda, no caso de ter nacionalidade portuguesa, estar amparado pelo Estatuto de Igualdade entre brasileiros e portugueses, com reconhecimento do gozo dos direitos pol\u00edticos, nos termos do par\u00e1grafo primeiro do artigo 12 da Constitui\u00e7\u00e3o Federal.<\/li><\/ul><\/li><li>5. O subitem 13.12 do Edital n\u00ba 1, de 06 de Outubro de 2021 fica exclu\u00eddo.<\/li><li>6. O subitem 16.5 do Edital n\u00ba 1, de 06 de Outubro de 2021 passa a vigorar com a seguinte reda\u00e7\u00e3o:<ul><li>16.5 Somente ser\u00e1 convocado para realiza\u00e7\u00e3o da prova pr\u00e1tica, o candidato ao cargo de T\u00e9cnico de Laborat\u00f3rio\/\u00c1rea aprovado na prova escrita objetiva e classificado em at\u00e9 10 (dez) vezes a quantidade de vagas (170 candidatos), respeitadas as vagas destinadas aos candidatos com defici\u00eancia e candidatos negros, conforme o perfil de aprova\u00e7\u00e3o definido nos subitens 18.1 e 18.2 deste Edital.<\/li><\/ul><\/li><li>7. Foram inseridos no item 21 do Edital n\u00ba 1, de 06 de Outubro de 2021, os seguintes subitens:<ul><li>21.18 Recursos contra o conte\u00fado do Edital n\u00ba 1, de 06 de Outubro de 2021 poder\u00e3o ser encaminhados \u00e0 Coordena\u00e7\u00e3o do Concurso, por meio do Painel do Concurso UFC, em formul\u00e1rio disponibilizado para tal fim no site https:\/\/www.ufc-concursos.com.br, no per\u00edodo compreendido entre as 10h do dia 19 de Outubro de 2021 e as 23:59h do dia 22 de Outubro de 2021.<\/li><li>21.18.1 O acesso ao Painel do Concurso se dar\u00e1 por meio do Login \u00danico do Governo Federal (Login GOV.BR).<\/li><li>21.18.2 Somente ser\u00e3o analisados os recursos encaminhados utilizando o formul\u00e1rio dispon\u00edvel no site e prazo indicado no subitem 21.18 deste Edital.<\/li><li>21.18.3 Admitir-se-\u00e1 um \u00fanico recurso por impetrante, desde que devidamente fundamentado.<\/li><li>21.18.4 Se julgado procedente o recurso interposto, resultando na modifica\u00e7\u00e3o deste Edital, ser\u00e1 feita nova publica\u00e7\u00e3o com as modifica\u00e7\u00f5es pertinentes.<\/li><li>21.18.5 Recursos cujo teor desrespeite a Coordena\u00e7\u00e3o do Concurso UFC ou as institui\u00e7\u00f5es envolvidas ser\u00e3o preliminarmente indeferidos.<\/li><li>21.18.6 A decis\u00e3o sobre os recursos ser\u00e1 divulgada no site do Concurso https:\/\/www.ufc-concursos.com.br, com a publica\u00e7\u00e3o do Edital retificador.<\/li><li>21.18.7 N\u00e3o ser\u00e3o encaminhadas respostas individuais aos impetrantes.<\/li><\/ul><\/li><\/ul>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-mudan-a-nos-conte-dos\">Mudan\u00e7a nos conte\u00fados<\/h3>\n\n\n\n<p>Quatro cargos do concurso UFC tiveram conte\u00fados republicados pelo edital deste dia 18 de outubro. S\u00e3o eles: T\u00e9cnico de Laborat\u00f3rio\/An\u00e1lises Qu\u00edmicas, T\u00e9cnico de Laborat\u00f3rio\/Estradas, T\u00e9cnico de laborat\u00f3rio\/Edifica\u00e7\u00f5es e T\u00e9cnico de Tecnologia da Informa\u00e7\u00e3o. Confira:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Os subitens 1.3.4, 1.3.5, 1.3.7 e 1.3.15, do Anexo I, do Edital n\u00ba 1, de 06 de Outubro de 2021, passam a vigorar com a seguinte reda\u00e7\u00e3o, respectivamente:<ul><li><strong>1.3.4 Cargo de T\u00e9cnico de Laborat\u00f3rio \/ An\u00e1lises Qu\u00edmicas<\/strong><ul><li>Fundamentos (f\u00edsicos e qu\u00edmicos) de fluoresc\u00eancia de raios x: O espectro eletromagn\u00e9tico e as t\u00e9cnicas anal\u00edticas, tabela peri\u00f3dica e as propriedades dos elementos qu\u00edmicos, a intera\u00e7\u00e3o da radia\u00e7\u00e3o com a mat\u00e9ria (teoria do espalhamento), a gera\u00e7\u00e3o de raios x, linhas espectrais, difra\u00e7\u00e3o e fluoresc\u00eancia de raios x. An\u00e1lises qualitativas por espectr\u00f4metros e tipos de espectr\u00f4metro de Fluoresc\u00eancia de Raios X (WD-XRF e ED-XRF): tubos, colimadores, filtros, monocromadores, detectores e condi\u00e7\u00f5es instrumentais; descri\u00e7\u00e3o do equipamento. An\u00e1lises quantitativas por FRX: calibra\u00e7\u00f5es, padr\u00f5es anal\u00edticos, fontes de erros (efeitos matriz, liga\u00e7\u00e3o qu\u00edmica e granula\u00e7\u00e3o) e tratamento do erro experimental, algarismos significativos, m\u00e9dia, desvio padr\u00e3o, limite de confian\u00e7a. T\u00e9cnicas de prepara\u00e7\u00e3o de amostras para FRX: teoria e pr\u00e1tica. Reagentes qu\u00edmicos: prepara\u00e7\u00e3o, manuseio e conserva\u00e7\u00e3o; Liga\u00e7\u00f5es qu\u00edmicas. T\u00e9cnicas de separa\u00e7\u00e3o e identifica\u00e7\u00e3o: destila\u00e7\u00e3o simples e fracionada, filtra\u00e7\u00e3o simples e a v\u00e1cuo, recristaliza\u00e7\u00e3o, parti\u00e7\u00e3o l\u00edquido-l\u00edquido, evapora\u00e7\u00e3o, cromatografia, ponto de fus\u00e3o. \u00c1cidos e bases. Manuten\u00e7\u00e3o e uso de instrumentos de laborat\u00f3rio de Qu\u00edmica. Normas de higiene e seguran\u00e7a de laborat\u00f3rio.<\/li><\/ul><\/li><li><strong>1.3.5 Cargo de T\u00e9cnico de Laborat\u00f3rio \/ Estradas<\/strong><ul><li>Solos: Amostragem de campo. Identifica\u00e7\u00e3o visual e t\u00e1til de amostras de solo. Classifica\u00e7\u00e3o dos solos com base nos resultados de laborat\u00f3rio e de campo. Determina\u00e7\u00e3o de \u00edndices f\u00edsicos (massa espec\u00edfica natural, dos s\u00f3lidos, seca, teor de umidade, \u00edndices de vazios, porosidade, grau de satura\u00e7\u00e3o). An\u00e1lise granulom\u00e9trica conjunta de solos (peneiramento e sedimenta\u00e7\u00e3o). Determina\u00e7\u00e3o dos limites de consist\u00eancia (limites de liquidez, plasticidade e contra\u00e7\u00e3o). Ensaio de compacta\u00e7\u00e3o Proctor. M\u00f3dulo de resili\u00eancia de solos. Deforma\u00e7\u00e3o permanente em solos. Fen\u00f4menos de capilaridade e permeabilidade. Ensaio de permeabilidade (cargas constante e vari\u00e1vel). Ensaio de adensamento. Pavimenta\u00e7\u00e3o: Caracteriza\u00e7\u00e3o tecnol\u00f3gica de agregados para pavimenta\u00e7\u00e3o (gradua\u00e7\u00e3o, limpeza, resist\u00eancia \u00e0 abras\u00e3o, propriedades de forma, absor\u00e7\u00e3o, adesividade ao ligante asf\u00e1ltico e massa espec\u00edfica). Caracteriza\u00e7\u00e3o b\u00e1sica de ligantes asf\u00e1lticos (penetra\u00e7\u00e3o, viscosidade, ponto de amolecimento e ponto de fulgor). Asfalto modificado por pol\u00edmero. Asfalto borracha. Emuls\u00e3o asf\u00e1ltica. Asfalto dilu\u00eddo de petr\u00f3leo. Estabiliza\u00e7\u00e3o granulom\u00e9trica e qu\u00edmica de camadas granulares. Dosagem e caracteriza\u00e7\u00e3o mec\u00e2nica de misturas asf\u00e1lticas densas. Tratamento superficial (TSS, TSD e TST). Microrrevestimento asf\u00e1ltico. Reciclagem de pavimentos asf\u00e1lticos. Seguran\u00e7a do trabalho e boas pr\u00e1ticas laboratoriais: Acidentes de trabalho. Preven\u00e7\u00e3o de acidentes. Equipamentos de prote\u00e7\u00e3o. Riscos ambientais. Mapa de riscos. Preven\u00e7\u00e3o e combate a inc\u00eandios. Sinaliza\u00e7\u00e3o. Normas Regulamentadoras.<\/li><\/ul><\/li><li><strong>1.3.7 Cargo T\u00e9cnico de laborat\u00f3rio\/Edifica\u00e7\u00f5es<\/strong><ul><li>Projetos civis: arquitet\u00f4nico, funda\u00e7\u00f5es, estrutural, hidrossanit\u00e1rio e el\u00e9trico. Produ\u00e7\u00e3o, aplica\u00e7\u00f5es e propriedades dos materiais: cimento Portland, cal, gesso, materiais cer\u00e2micos, vidros, madeira, materiais met\u00e1licos, materiais betuminosos, tintas, pastas ciment\u00edcias, argamassas, concretos e grautes. Componentes de materiais comp\u00f3sitos: aglomerantes, agregados, fibras, adi\u00e7\u00f5es minerais, aditivos qu\u00edmicos. Controle tecnol\u00f3gico de materiais: recebimento de materiais em obra, ensaios de qualidade em blocos cer\u00e2micos, telhas, placas cer\u00e2micas e outros elementos; ensaios de qualidade em madeiras; ensaios de qualidade em barras de a\u00e7o para concreto armado, ensaios de qualidade em tintas e materiais betuminosos. Ensaios de qualidade em pastas, argamassas, concretos e grautes de cimento Portland, ensaios de caracteriza\u00e7\u00e3o de agregados e cimentos. Seguran\u00e7a do trabalho e boas pr\u00e1ticas laboratoriais: an\u00e1lise preliminar de risco, mapas de risco, lista de verifica\u00e7\u00e3o, prote\u00e7\u00e3o contra riscos f\u00edsicos, qu\u00edmicos, biol\u00f3gicos, ergon\u00f4micos e risco de acidentes. Ensaios mec\u00e2nicos de elementos estruturais: an\u00e1lise experimental de tens\u00f5es e deforma\u00e7\u00f5es, ensaios est\u00e1ticos e din\u00e2micos em elementos estruturais, resist\u00eancia \u00e0 compress\u00e3o, resist\u00eancia \u00e0 flex\u00e3o, resist\u00eancia \u00e0 tra\u00e7\u00e3o, m\u00f3dulo de elasticidade, coeficiente de Poisson, tenacidade e flu\u00eancia. Normas regulamentadoras. NBRs.<\/li><\/ul><\/li><li><strong>1.3.15 Cargo de T\u00e9cnico de Tecnologia da Informa\u00e7\u00e3o<\/strong><\/li><\/ul><\/li><\/ul>\n\n\n\n<p>9. Os Anexos II e III do Edital n\u00ba 1, de 06 de Outubro de 2021, passam a vigorar com a reda\u00e7\u00e3o a seguir apresentada.<\/p>\n\n\n\n<p>10. Os demais itens e Anexos do Edital n\u00ba 1\/2021, de 06 de Outubro de 2021, permanecem inalterados.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Cargos, vagas e remunera\u00e7\u00f5es do edital&nbsp;UFC <\/h2>\n\n\n\n<h3 class=\"wp-block-heading\">N\u00edvel m\u00e9dio\/t\u00e9cnico<\/h3>\n\n\n\n<figure class=\"wp-block-table is-style-stripes\"><table class=\"has-background has-fixed-layout\" style=\"background-color:#c2dae9\"><thead><tr><th class=\"has-text-align-center\" data-align=\"center\">Cargos<\/th><th class=\"has-text-align-center\" data-align=\"center\">Vagas<\/th><th class=\"has-text-align-center\" data-align=\"center\">Sal\u00e1rio<\/th><\/tr><\/thead><tbody><tr><td class=\"has-text-align-center\" data-align=\"center\">Assistente em Administra\u00e7\u00e3o<\/td><td class=\"has-text-align-center\" data-align=\"center\">20<\/td><td class=\"has-text-align-center\" data-align=\"center\">Vencimento<br \/>B\u00e1sico<br \/>R$ 2.446,96 + Aux\u00edlio Alimenta\u00e7\u00e3o R$ 458,00<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">T\u00e9cnico de Laborat\u00f3rio\/Biotecnologia<\/td><td class=\"has-text-align-center\" data-align=\"center\">01<\/td><td class=\"has-text-align-center\" data-align=\"center\"> Vencimento<br \/>B\u00e1sico<br \/>R$ 2.446,96 + Aux\u00edlio Alimenta\u00e7\u00e3o R$ 458,00 <\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">T\u00e9cnico de Laborat\u00f3rio\/Comunica\u00e7\u00e3o Visual<\/td><td class=\"has-text-align-center\" data-align=\"center\">02<\/td><td class=\"has-text-align-center\" data-align=\"center\"> Vencimento<br \/>B\u00e1sico<br \/>R$ 2.446,96 + Aux\u00edlio Alimenta\u00e7\u00e3o R$ 458,00 <\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">T\u00e9cnico de Laborat\u00f3rio\/Desenvolvimento de Sistemas<\/td><td class=\"has-text-align-center\" data-align=\"center\">01<\/td><td class=\"has-text-align-center\" data-align=\"center\"> Vencimento<br \/>B\u00e1sico<br \/>R$ 2.446,96 + Aux\u00edlio Alimenta\u00e7\u00e3o R$ 458,00 <\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">T\u00e9cnico de Laborat\u00f3rio\/ Edifica\u00e7\u00f5es<\/td><td class=\"has-text-align-center\" data-align=\"center\">01<\/td><td class=\"has-text-align-center\" data-align=\"center\"> Vencimento<br \/>B\u00e1sico<br \/>R$ 2.446,96 + Aux\u00edlio Alimenta\u00e7\u00e3o R$ 458,00 <\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">T\u00e9cnico de Laborat\u00f3rio\/ Estradas<\/td><td class=\"has-text-align-center\" data-align=\"center\">01<\/td><td class=\"has-text-align-center\" data-align=\"center\"> Vencimento<br \/>B\u00e1sico<br \/>R$ 2.446,96 + Aux\u00edlio Alimenta\u00e7\u00e3o R$ 458,00 <\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">T\u00e9cnico de Laborat\u00f3rio\/ An\u00e1lises Qu\u00edmicas<\/td><td class=\"has-text-align-center\" data-align=\"center\">01<\/td><td class=\"has-text-align-center\" data-align=\"center\"> Vencimento<br \/>B\u00e1sico<br \/>R$ 2.446,96 + Aux\u00edlio Alimenta\u00e7\u00e3o R$ 458,00  <\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">T\u00e9cnico de Laborat\u00f3rio\/ Geologia<\/td><td class=\"has-text-align-center\" data-align=\"center\">01<\/td><td class=\"has-text-align-center\" data-align=\"center\"> Vencimento<br \/>B\u00e1sico<br \/>R$ 2.446,96 + Aux\u00edlio Alimenta\u00e7\u00e3o R$ 458,00  <\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">T\u00e9cnico de Laborat\u00f3rio\/ Hidrologia<\/td><td class=\"has-text-align-center\" data-align=\"center\">01<\/td><td class=\"has-text-align-center\" data-align=\"center\"> Vencimento<br \/>B\u00e1sico<br \/>R$ 2.446,96 + Aux\u00edlio Alimenta\u00e7\u00e3o R$ 458,00  <\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">T\u00e9cnico de Laborat\u00f3rio\/Meio Ambiente<\/td><td class=\"has-text-align-center\" data-align=\"center\">01<\/td><td class=\"has-text-align-center\" data-align=\"center\"> Vencimento<br \/>B\u00e1sico<br \/>R$ 2.446,96 + Aux\u00edlio Alimenta\u00e7\u00e3o R$ 458,00 <\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">T\u00e9cnico de Laborat\u00f3rio\/ Multimidia<\/td><td class=\"has-text-align-center\" data-align=\"center\">01<\/td><td class=\"has-text-align-center\" data-align=\"center\"> Vencimento<br \/>B\u00e1sico<br \/>R$ 2.446,96 + Aux\u00edlio Alimenta\u00e7\u00e3o R$ 458,00  <\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\"><br \/>T\u00e9cnico de Laborat\u00f3rio\/ Produ\u00e7\u00e3o de \u00c1udio e V\u00eddeo<\/td><td class=\"has-text-align-center\" data-align=\"center\">02<\/td><td class=\"has-text-align-center\" data-align=\"center\"> Vencimento<br \/>B\u00e1sico<br \/>R$ 2.446,96 + Aux\u00edlio Alimenta\u00e7\u00e3o R$ 458,00  <\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\"><br \/>T\u00e9cnico de Laborat\u00f3rio\/Pr\u00f3tese Dent\u00e1ria<\/td><td class=\"has-text-align-center\" data-align=\"center\">01<\/td><td class=\"has-text-align-center\" data-align=\"center\"> Vencimento<br \/>B\u00e1sico<br \/>R$ 2.446,96 + Aux\u00edlio Alimenta\u00e7\u00e3o R$ 458,00  <\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">T\u00e9cnico de Laborat\u00f3rio\/Saneamento<\/td><td class=\"has-text-align-center\" data-align=\"center\">01<\/td><td class=\"has-text-align-center\" data-align=\"center\"> Vencimento<br \/>B\u00e1sico<br \/>R$ 2.446,96 + Aux\u00edlio Alimenta\u00e7\u00e3o R$ 458,00  <\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">T\u00e9cnico de Laborat\u00f3rio\/Tecnologia da Informa\u00e7\u00e3o<\/td><td class=\"has-text-align-center\" data-align=\"center\">05<\/td><td class=\"has-text-align-center\" data-align=\"center\"> Vencimento<br \/>B\u00e1sico<br \/>R$ 2.446,96 + Aux\u00edlio Alimenta\u00e7\u00e3o R$ 458,00  <\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">N\u00edvel superior<\/h3>\n\n\n\n<figure class=\"wp-block-table is-style-stripes\"><table class=\"has-background has-fixed-layout\" style=\"background-color:#c2dae9\"><thead><tr><th class=\"has-text-align-center\" data-align=\"center\">Cargos<\/th><th class=\"has-text-align-center\" data-align=\"center\">Vagas<\/th><th class=\"has-text-align-center\" data-align=\"center\">Sal\u00e1rio<\/th><\/tr><\/thead><tbody><tr><td class=\"has-text-align-center\" data-align=\"center\">Administrador<\/td><td class=\"has-text-align-center\" data-align=\"center\">07<\/td><td class=\"has-text-align-center\" data-align=\"center\">Vencimento B\u00e1sico<br \/>R$ 4.180,66 + Aux\u00edlio Alimenta\u00e7\u00e3o R$ 458,00<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">Analista de Tecnologia da Informa\u00e7\u00e3o<\/td><td class=\"has-text-align-center\" data-align=\"center\">08<\/td><td class=\"has-text-align-center\" data-align=\"center\">Vencimento B\u00e1sico<br \/>R$ 4.180,66 + Aux\u00edlio Alimenta\u00e7\u00e3o R$ 458,00<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">Arquivista<\/td><td class=\"has-text-align-center\" data-align=\"center\">03<\/td><td class=\"has-text-align-center\" data-align=\"center\">Vencimento B\u00e1sico<br \/>R$ 4.180,66 + Aux\u00edlio Alimenta\u00e7\u00e3o R$ 458,00<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">Assistente Social<\/td><td class=\"has-text-align-center\" data-align=\"center\">04<\/td><td class=\"has-text-align-center\" data-align=\"center\">Vencimento B\u00e1sico<br \/>R$ 4.180,66 + Aux\u00edlio Alimenta\u00e7\u00e3o R$ 458,00<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">Auditor<\/td><td class=\"has-text-align-center\" data-align=\"center\">01<\/td><td class=\"has-text-align-center\" data-align=\"center\">Vencimento B\u00e1sico<br \/>R$ 4.180,66 + Aux\u00edlio Alimenta\u00e7\u00e3o R$ 458,00<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">Bibliotec\u00e1rio\/Documentalista<\/td><td class=\"has-text-align-center\" data-align=\"center\">02<\/td><td class=\"has-text-align-center\" data-align=\"center\">Vencimento B\u00e1sico<br \/>R$ 4.180,66 + Aux\u00edlio Alimenta\u00e7\u00e3o R$ 458,00<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">Engenheiro Civil<\/td><td class=\"has-text-align-center\" data-align=\"center\">01<\/td><td class=\"has-text-align-center\" data-align=\"center\">Vencimento B\u00e1sico<br \/>R$ 4.180,66 + Aux\u00edlio Alimenta\u00e7\u00e3o R$ 458,00<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">Farmac\u00eautico<\/td><td class=\"has-text-align-center\" data-align=\"center\">01<\/td><td class=\"has-text-align-center\" data-align=\"center\">Vencimento B\u00e1sico<br \/>R$ 4.180,66 + Aux\u00edlio Alimenta\u00e7\u00e3o R$ 458,00<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">Ge\u00f3logo<\/td><td class=\"has-text-align-center\" data-align=\"center\">01<\/td><td class=\"has-text-align-center\" data-align=\"center\">Vencimento B\u00e1sico<br \/>R$ 4.180,66 + Aux\u00edlio Alimenta\u00e7\u00e3o R$ 458,00<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">M\u00e9dico\/Psiquiatra<\/td><td class=\"has-text-align-center\" data-align=\"center\">02<\/td><td class=\"has-text-align-center\" data-align=\"center\">Vencimento B\u00e1sico<br \/>R$ 4.180,66 + Aux\u00edlio Alimenta\u00e7\u00e3o R$ 458,00<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">Nutricionista<\/td><td class=\"has-text-align-center\" data-align=\"center\">02<\/td><td class=\"has-text-align-center\" data-align=\"center\">Vencimento B\u00e1sico<br \/>R$ 4.180,66 + Aux\u00edlio Alimenta\u00e7\u00e3o R$ 458,00<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">Pedagogo<\/td><td class=\"has-text-align-center\" data-align=\"center\">03<\/td><td class=\"has-text-align-center\" data-align=\"center\">Vencimento B\u00e1sico<br \/>R$ 4.180,66 + Aux\u00edlio Alimenta\u00e7\u00e3o R$ 458,00<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">Produtor Cultural<\/td><td class=\"has-text-align-center\" data-align=\"center\">01<\/td><td class=\"has-text-align-center\" data-align=\"center\">Vencimento B\u00e1sico<br \/>R$ 4.180,66 + Aux\u00edlio Alimenta\u00e7\u00e3o R$ 458,00<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">T\u00e9cnico em Assuntos Educacionais<\/td><td class=\"has-text-align-center\" data-align=\"center\">03<\/td><td class=\"has-text-align-center\" data-align=\"center\"> Vencimento B\u00e1sico<br \/>R$ 4.180,66 + Aux\u00edlio Alimenta\u00e7\u00e3o R$ 458,00 <\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Etapas do edital&nbsp;UFC  <\/h2>\n\n\n\n<h3 class=\"wp-block-heading\">Prova Escrita Objetiva<\/h3>\n\n\n\n<p>O concurso UFC ter\u00e1 Prova Escrita Objetiva com 4h de dura\u00e7\u00e3o, come\u00e7ando \u00e0s 13h e terminando \u00e0s 17h, no dia 30 de janeiro de 2022. Ser\u00e3o exigidas as seguintes disciplinas por cargo ofertado:<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">N\u00edvel m\u00e9dio\/t\u00e9cnico<\/h4>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"156\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/10\/07072114\/captura-de-tela-2021-10-07-as-05.webp\" alt=\"provas concurso UFC\" class=\"wp-image-879437\" srcset=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/10\/07072114\/captura-de-tela-2021-10-07-as-05.webp 768w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/10\/07072114\/captura-de-tela-2021-10-07-as-05-300x61.webp 300w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/10\/07072114\/captura-de-tela-2021-10-07-as-05-610x124.webp 610w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/figure><\/div>\n\n\n\n<h4 class=\"wp-block-heading\">N\u00edvel superior<\/h4>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"169\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/10\/07072129\/captura-de-tela-2021-10-07-as-05-1.webp\" alt=\"provas concurso UFC\" class=\"wp-image-879438\" srcset=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/10\/07072129\/captura-de-tela-2021-10-07-as-05-1.webp 768w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/10\/07072129\/captura-de-tela-2021-10-07-as-05-1-300x66.webp 300w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/10\/07072129\/captura-de-tela-2021-10-07-as-05-1-610x134.webp 610w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/figure><\/div>\n\n\n\n<h3 class=\"wp-block-heading\">Prova Pr\u00e1tica<\/h3>\n\n\n\n<p>Os candidatos ao cargo de T\u00e9cnico de Laborat\u00f3rio\/\u00e1rea do concurso UFC ainda enfrentar\u00e3o a Prova Pr\u00e1tica, de car\u00e1ter eliminat\u00f3rio e classificat\u00f3rio, que ser\u00e1 constitu\u00edda de quatro itens de avalia\u00e7\u00e3o, valendo at\u00e9 100 pontos.<\/p>\n\n\n\n<p>Somente ser\u00e1 convocado para realiza\u00e7\u00e3o desta avalia\u00e7\u00e3o, o candidato aprovado no exame anterior e classificado em at\u00e9 10 (dez) vezes a quantidade de vagas (220 candidatos). <\/p>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<h2 class=\"has-text-align-center wp-block-heading\" id=\"curso\"><strong>Quer estudar para o edital UFC?<\/strong><\/h2>\n\n\n\n<div class=\"container\" id=\"boxes\">\n  <div class=\"row\">\n\n    <div class=\"col-sm\">\n      <div class=\"banner-adm\" id=\"box-assinatura\">\n        <h3 class=\"titulo-assinatura\">Concurso UFC<\/h3>\n        <p class=\"subtitulo-assinatura\">Conhe\u00e7a os cursos<\/p>\n        <div class=\"box-botao\">\n          <a class=\"btn-assinatura\" target=\"_blank\" href=\"https:\/\/www.estrategiaconcursos.com.br\/pesquisa\/?q=UFC\" rel=\"noopener\">Conhe\u00e7a mais<\/a>\n        <\/div>\n      <\/div>\n      \n    <\/div>\n\n  <\/div>\n<\/div>\n\n\n\n<div class=\"container\" id=\"boxes\">\n  <div class=\"row\">\n\n    <div class=\"col-sm\">\n      <div class=\"estrategia\" id=\"box-assinatura\">\n        <h3 class=\"titulo-assinatura\"> Concursos P\u00fablicos\n        <p class=\"subtitulo-assinatura\">Assinatura de 1 ano ou 2 anos<\/p>\n        <div class=\"box-botao\">\n          <a class=\"btn-assinatura\" target=\"_blank\" href=\"https:\/\/www.estrategiaconcursos.com.br\/assinaturas\/\" role=\"button\" rel=\"noopener noreferrer\">ASSINE AGORA<\/a>\n        <\/div>\n      <\/h3><\/div><\/div><\/div><\/div>\n\n\n\n<h2 class=\"has-text-align-center wp-block-heading\">Quer saber tudo sobre concursos previstos?<br \/>Confira nossos artigos!<\/h2>\n\n\n\n<ul class=\"wp-block-list\"><li><a target=\"_blank\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-abertos\/\" rel=\"noreferrer noopener\">Concursos abertos<\/a><\/li><li><a target=\"_blank\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-2021\/\" rel=\"noreferrer noopener\">Concursos 2021<\/a><\/li><li><a target=\"_blank\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-2022\/\" rel=\"noreferrer noopener\">Concursos 2022<\/a><\/li><\/ul>\n\n\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/04\/15205809\/ficha-tecnica-1-1024x632-1-1.png\" alt=\"Informa\u00e7\u00f5es do edital UFC\" class=\"wp-image-715231\" width=\"254\" height=\"157\" srcset=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/04\/15205809\/ficha-tecnica-1-1024x632-1-1.png 1024w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/04\/15205809\/ficha-tecnica-1-1024x632-1-1-300x185.png 300w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/04\/15205809\/ficha-tecnica-1-1024x632-1-1-768x474.png 768w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/04\/15205809\/ficha-tecnica-1-1024x632-1-1-610x376.png 610w\" sizes=\"auto, (max-width: 254px) 100vw, 254px\" \/><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"ficha\">Informa\u00e7\u00f5es do edital UFC<\/h3>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>Data da prova:<\/strong> 30\/01\/2022<\/li><li><strong>Vagas:&nbsp;<\/strong>81<\/li><li><strong>Cargo:<\/strong>&nbsp;diversos<\/li><li><strong>Escolaridade:<\/strong> N\u00edveis m\u00e9dio\/t\u00e9cnico e superior <\/li><li><strong>Banca:&nbsp;<\/strong>Cetrede<\/li><li><strong>Edital:<\/strong> <a href=\"https:\/\/www.in.gov.br\/en\/web\/dou\/-\/edital-n-1-de-6-de-outubro-de-2021-351254381\" target=\"_blank\" rel=\"noreferrer noopener\">Edital UFC 2021<\/a><\/li><\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Foram prorrogadas at\u00e9 o dia 5 de dezembro as inscri\u00e7\u00f5es do edital UFC. As provas ser\u00e3o aplicadas em\u00a030 de janeiro de 2022. S\u00e3o ofertadas 81 vagas, sendo 42\u00a0para fun\u00e7\u00f5es de n\u00edvel m\u00e9dio\/t\u00e9cnico e 39 para superior. A banca respons\u00e1vel pela sele\u00e7\u00e3o da Universidade Federal do Cear\u00e1 \u00e9 a&nbsp;Funda\u00e7\u00e3o Cetrede. Os candidatos aprovados no concurso ser\u00e3o [&hellip;]<\/p>\n","protected":false},"author":2018,"featured_media":875565,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"post_tipo":"article","footnotes":""},"categories":[3766,220219],"tags":[],"tax_estado":[219969],"class_list":["post-879436","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-educacional","category-noticias","tax_estado-ce"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.2 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Edital UFC: inscri\u00e7\u00f5es prorrogadas! Prova em 30\/01<\/title>\n<meta name=\"description\" content=\"Edital UFC: inscri\u00e7\u00f5es prorrogadas! 81 vagas para cargos de n\u00edveis m\u00e9dio\/t\u00e9cnico e superior. Provas em janeiro de 2022. Confira!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/edital-ufc\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Edital UFC: inscri\u00e7\u00f5es prorrogadas! Prova em 30\/01\" \/>\n<meta property=\"og:description\" content=\"Edital UFC: inscri\u00e7\u00f5es prorrogadas! 81 vagas para cargos de n\u00edveis m\u00e9dio\/t\u00e9cnico e superior. Provas em janeiro de 2022. Confira!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/edital-ufc\/\" \/>\n<meta property=\"og:site_name\" content=\"Estrat\u00e9gia Concursos\" \/>\n<meta property=\"article:published_time\" content=\"2021-11-29T03:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-11-30T15:04:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/03\/01170554\/ufc.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"984\" \/>\n\t<meta property=\"og:image:height\" content=\"651\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"B\u00e1rbara Carvalho Santos\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:site\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"B\u00e1rbara Carvalho Santos\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"9 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/edital-ufc\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/edital-ufc\/\"},\"author\":{\"name\":\"B\u00e1rbara Carvalho Santos\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/e3882259fa157d54c44c21f4ee4e0e60\"},\"headline\":\"Edital UFC: inscri\u00e7\u00f5es prorrogadas! Prova em 30\/01\",\"datePublished\":\"2021-11-29T03:00:00+00:00\",\"dateModified\":\"2021-11-30T15:04:03+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/edital-ufc\/\"},\"wordCount\":2109,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/edital-ufc\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/03\/01170554\/ufc.jpg\",\"articleSection\":[\"Educa\u00e7\u00e3o\",\"\u00daltimas not\u00edcias\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/edital-ufc\/#respond\"]}],\"copyrightYear\":\"2021\",\"copyrightHolder\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/edital-ufc\/\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/edital-ufc\/\",\"name\":\"Edital UFC: inscri\u00e7\u00f5es prorrogadas! Prova em 30\/01\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/edital-ufc\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/edital-ufc\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/03\/01170554\/ufc.jpg\",\"datePublished\":\"2021-11-29T03:00:00+00:00\",\"dateModified\":\"2021-11-30T15:04:03+00:00\",\"description\":\"Edital UFC: inscri\u00e7\u00f5es prorrogadas! 81 vagas para cargos de n\u00edveis m\u00e9dio\/t\u00e9cnico e superior. Provas em janeiro de 2022. Confira!\",\"breadcrumb\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/edital-ufc\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/edital-ufc\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/edital-ufc\/#primaryimage\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/03\/01170554\/ufc.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/03\/01170554\/ufc.jpg\",\"width\":984,\"height\":651,\"caption\":\"concurso UFC\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/edital-ufc\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Edital UFC: inscri\u00e7\u00f5es prorrogadas! Prova em 30\/01\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"name\":\"Estrat\u00e9gia Concursos\",\"description\":\"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.\",\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\",\"name\":\"Estrat\u00e9gia Concursos\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"width\":230,\"height\":60,\"caption\":\"Estrat\u00e9gia Concursos\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/EstratConcursos\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/e3882259fa157d54c44c21f4ee4e0e60\",\"name\":\"B\u00e1rbara Carvalho Santos\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/353300f73140f779692b9be2b39f434d1341e4e34c7f55bd5a990fe29ef352eb?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/353300f73140f779692b9be2b39f434d1341e4e34c7f55bd5a990fe29ef352eb?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/353300f73140f779692b9be2b39f434d1341e4e34c7f55bd5a990fe29ef352eb?s=96&d=mm&r=g\",\"caption\":\"B\u00e1rbara Carvalho Santos\"},\"description\":\"M\u00e3e e jornalista formada pela UNIP, possui ampla experi\u00eancia na cobertura de entretenimento em grandes ve\u00edculos, como o site da CNN, RedeTV! e Estrat\u00e9gia Educacional. Atuou tamb\u00e9m em ag\u00eancias de marketing, produtoras musicais e assessorias de imprensa, com foco especial no trabalho com personalidades p\u00fablicas. Atualmente, integra a equipe do Estrat\u00e9gia Concursos, onde \u00e9 respons\u00e1vel pela produ\u00e7\u00e3o de conte\u00fados estrat\u00e9gicos voltados para o setor de concursos p\u00fablicos, com destaque para a \u00e1rea fiscal, gest\u00e3o, controle, concursos administrativos e Minist\u00e9rios participantes do CNU, al\u00e9m de diversos \u00f3rg\u00e3os federais. Tem como miss\u00e3o transformar informa\u00e7\u00f5es complexas em conte\u00fados acess\u00edveis, relevantes e de alto valor para quem sonha com uma carreira no servi\u00e7o p\u00fablico.\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/barbara-santos\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Edital UFC: inscri\u00e7\u00f5es prorrogadas! Prova em 30\/01","description":"Edital UFC: inscri\u00e7\u00f5es prorrogadas! 81 vagas para cargos de n\u00edveis m\u00e9dio\/t\u00e9cnico e superior. Provas em janeiro de 2022. Confira!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.estrategiaconcursos.com.br\/blog\/edital-ufc\/","og_locale":"pt_BR","og_type":"article","og_title":"Edital UFC: inscri\u00e7\u00f5es prorrogadas! Prova em 30\/01","og_description":"Edital UFC: inscri\u00e7\u00f5es prorrogadas! 81 vagas para cargos de n\u00edveis m\u00e9dio\/t\u00e9cnico e superior. Provas em janeiro de 2022. Confira!","og_url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/edital-ufc\/","og_site_name":"Estrat\u00e9gia Concursos","article_published_time":"2021-11-29T03:00:00+00:00","article_modified_time":"2021-11-30T15:04:03+00:00","og_image":[{"width":984,"height":651,"url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/03\/01170554\/ufc.jpg","type":"image\/jpeg"}],"author":"B\u00e1rbara Carvalho Santos","twitter_card":"summary_large_image","twitter_creator":"@EstratConcursos","twitter_site":"@EstratConcursos","twitter_misc":{"Escrito por":"B\u00e1rbara Carvalho Santos","Est. tempo de leitura":"9 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/edital-ufc\/#article","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/edital-ufc\/"},"author":{"name":"B\u00e1rbara Carvalho Santos","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/e3882259fa157d54c44c21f4ee4e0e60"},"headline":"Edital UFC: inscri\u00e7\u00f5es prorrogadas! Prova em 30\/01","datePublished":"2021-11-29T03:00:00+00:00","dateModified":"2021-11-30T15:04:03+00:00","mainEntityOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/edital-ufc\/"},"wordCount":2109,"commentCount":0,"publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/edital-ufc\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/03\/01170554\/ufc.jpg","articleSection":["Educa\u00e7\u00e3o","\u00daltimas not\u00edcias"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/edital-ufc\/#respond"]}],"copyrightYear":"2021","copyrightHolder":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/edital-ufc\/","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/edital-ufc\/","name":"Edital UFC: inscri\u00e7\u00f5es prorrogadas! Prova em 30\/01","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/edital-ufc\/#primaryimage"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/edital-ufc\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/03\/01170554\/ufc.jpg","datePublished":"2021-11-29T03:00:00+00:00","dateModified":"2021-11-30T15:04:03+00:00","description":"Edital UFC: inscri\u00e7\u00f5es prorrogadas! 81 vagas para cargos de n\u00edveis m\u00e9dio\/t\u00e9cnico e superior. Provas em janeiro de 2022. Confira!","breadcrumb":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/edital-ufc\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/edital-ufc\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/edital-ufc\/#primaryimage","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/03\/01170554\/ufc.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/03\/01170554\/ufc.jpg","width":984,"height":651,"caption":"concurso UFC"},{"@type":"BreadcrumbList","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/edital-ufc\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.estrategiaconcursos.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Edital UFC: inscri\u00e7\u00f5es prorrogadas! Prova em 30\/01"}]},{"@type":"WebSite","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","name":"Estrat\u00e9gia Concursos","description":"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.","publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization","name":"Estrat\u00e9gia Concursos","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","width":230,"height":60,"caption":"Estrat\u00e9gia Concursos"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/EstratConcursos"]},{"@type":"Person","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/e3882259fa157d54c44c21f4ee4e0e60","name":"B\u00e1rbara Carvalho Santos","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/353300f73140f779692b9be2b39f434d1341e4e34c7f55bd5a990fe29ef352eb?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/353300f73140f779692b9be2b39f434d1341e4e34c7f55bd5a990fe29ef352eb?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/353300f73140f779692b9be2b39f434d1341e4e34c7f55bd5a990fe29ef352eb?s=96&d=mm&r=g","caption":"B\u00e1rbara Carvalho Santos"},"description":"M\u00e3e e jornalista formada pela UNIP, possui ampla experi\u00eancia na cobertura de entretenimento em grandes ve\u00edculos, como o site da CNN, RedeTV! e Estrat\u00e9gia Educacional. Atuou tamb\u00e9m em ag\u00eancias de marketing, produtoras musicais e assessorias de imprensa, com foco especial no trabalho com personalidades p\u00fablicas. Atualmente, integra a equipe do Estrat\u00e9gia Concursos, onde \u00e9 respons\u00e1vel pela produ\u00e7\u00e3o de conte\u00fados estrat\u00e9gicos voltados para o setor de concursos p\u00fablicos, com destaque para a \u00e1rea fiscal, gest\u00e3o, controle, concursos administrativos e Minist\u00e9rios participantes do CNU, al\u00e9m de diversos \u00f3rg\u00e3os federais. Tem como miss\u00e3o transformar informa\u00e7\u00f5es complexas em conte\u00fados acess\u00edveis, relevantes e de alto valor para quem sonha com uma carreira no servi\u00e7o p\u00fablico.","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/barbara-santos\/"}]}},"_links":{"self":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/879436","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/users\/2018"}],"replies":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/comments?post=879436"}],"version-history":[{"count":9,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/879436\/revisions"}],"predecessor-version":[{"id":919013,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/879436\/revisions\/919013"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media\/875565"}],"wp:attachment":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media?parent=879436"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/categories?post=879436"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tags?post=879436"},{"taxonomy":"tax_estado","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tax_estado?post=879436"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}