{"id":87650,"date":"2020-07-22T22:30:00","date_gmt":"2020-07-23T01:30:00","guid":{"rendered":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?p=87650"},"modified":"2022-10-13T10:10:51","modified_gmt":"2022-10-13T13:10:51","slug":"temas-de-redacao-para-voce-treinar","status":"publish","type":"post","link":"https:\/\/www.estrategiaconcursos.com.br\/blog\/temas-de-redacao-para-voce-treinar\/","title":{"rendered":"Temas de reda\u00e7\u00e3o para Concursos P\u00fablicos &#8211; 2020"},"content":{"rendered":"<p>Prof. Rapha chegando na \u00e1rea para trazer uma lista atualizada de <strong>temas de reda\u00e7\u00e3o para concursos p\u00fablicos 2020.<\/strong><\/p>\n<p><strong>1. Saneamento B\u00e1sico:<\/strong><\/p>\n<p>Saneamento b\u00e1sico est\u00e1 na agenda das pol\u00edticas p\u00fablicas do Brasil. Essa problem\u00e1tica envolve princ\u00edpios b\u00e1sicos de cidadania e afeta diretamente a sa\u00fade p\u00fablica. Infelizmente, o acesso \u00e0 agua tratada n\u00e3o \u00e9 universal em boa parte dos mun\u00edcipios brasileiros, os quais, tamb\u00e9m, n\u00e3o contam com coleta e tratamento do esgoto.\u00a0 Ademais, o novo marco do saneamento b\u00e1sico permite a privatiza\u00e7\u00e3o dos servi\u00e7os, com a justifica de que somente a iniciativa privada teria recursos para fazer investimento e de que as companhias estatais s\u00e3o ineficientes. Por outro lado, os cr\u00edticos alegam que a \u00e1gua n\u00e3o poder ser vista como um produto e que tal marco poder\u00e1 encarecer as tarifas, aumentando ainda mais as desigualdes.<\/p>\n<p><b>2. Viol\u00eancia Urbana:<\/b><\/p>\n<p><b><\/b>Viol\u00eancia Urbana abrange v\u00e1rios temas como, por exemplo: viol\u00eancia contra \u00e0s mulheres, crian\u00e7as e adolescentes, jovens, idosos, maus tratos aos animais, etc. Al\u00e9m desses, h\u00e1 a quest\u00e3o do <em>bullyng <\/em>nas escolas, as brigas de torcidas organizadas e os conflitos no tr\u00e2nsito.<\/p>\n<p>Um bom conceito para ser aplicado \u00e9 o de cultura da viol\u00eancia, isto \u00e9, uma predisposi\u00e7\u00e3o de n\u00f3s brasileiros resolvermos nossos conflitos por meio da agress\u00e3o, e n\u00e3o por meio do di\u00e1logo e das institui\u00e7\u00f5es. Esse conceito est\u00e1 relacionado \u00e0s experi\u00eancias hist\u00f3ricas de autoritarismo em nosso pa\u00eds que permeia ainda hoje as nossas rela\u00e7\u00f5es sociais.<\/p>\n<p>Uma boa alus\u00e3o cinematogr\u00e1fica \u00e9 o filme coringa, porque a partir dele d\u00e1 para refletir sobre a viol\u00eancia cotidiana, banalidade do mal (conceito da fil\u00f3sofa Hanna Arendt) e imperativo \u00e0 felicidade.<\/p>\n<p>3<strong>. Conflitos migrat\u00f3rios no Brasil:<\/strong><\/p>\n<p>O Brasil est\u00e1 enfrentando problemas com a imigra\u00e7\u00e3o haitiana e venezuelana. Diferente da maioria dos pa\u00edses europeus e dos E.U.A, o nosso pa\u00eds adota uma pol\u00edtica de tratamento digno aos imigrantes &#8211; conferir a Lei de Migra\u00e7\u00e3o de 2017.<\/p>\n<p>\u00c9 importante o candidato movimentar conhecimentos sobre etnocentrismo, xenofobismo, alteridade, empatia. Outra reflex\u00e3o, que atinge diretamente a m\u00e3o de obra imigrante, \u00e9 o trabalho escravo contempor\u00e2neo.<\/p>\n<p><b>4. Urbaniza\u00e7\u00e3o e Mobilidade Urbana:<\/b><\/p>\n<p><b><\/b>Costumo dizer que esses dois temas s\u00e3o cl\u00e1ssicos. \u00c9 bom ficar sempre atento, porque s\u00e3o queridinhos das bancas. Assim, a sua produ\u00e7\u00e3o textual deve abordar o direito \u00e0 cidade qualidade de vida, segrega\u00e7\u00e3o socioespacial, democratiza\u00e7\u00e3o dos espa\u00e7os p\u00fablicos.<\/p>\n<p>5<strong>. \u00c9tica na Sociedade Contempor\u00e2nea<\/strong><\/p>\n<p>Esse \u00e9 um tema que j\u00e1 apareceu em alguns certames e pelo contexto atual, tanto em \u00e2mbito nacional como no internacional, \u00e9 um bom assunto. Eu n\u00e3o abriria m\u00e3o dos conceitos cl\u00e1ssicos de \u00e9tica dos fil\u00f3sofos Arist\u00f3teles e Kant.<\/p>\n<p>6<b>. Mudan\u00e7as no Mundo do Trabalho<\/b><\/p>\n<p><b><\/b>Esse \u00e9 um tema potencial para ser cobrado nos mais diversos certames, uma vez que est\u00e1 presente no nosso dia a dia. S\u00e3o v\u00e1rias mudan\u00e7as acontecendo, que v\u00e3o desde as reformas trabalhistas e previdenci\u00e1rias \u00e0s modifica\u00e7\u00f5es na rela\u00e7\u00f5es interpessoais, devido ao excesso de trabalho por meio da internert (aplicativos). Aqui, o candidato pode debater a sociedade do cansa\u00e7o, a era de incertezas (desemprego e desestabiliza\u00e7\u00e3o), flexibilidade, mudan\u00e7as na organiza\u00e7\u00e3o produtiva (toyotismo), uso de tecnologias no trabalho, etc.<\/p>\n<p>Ficar atento \u00e0s discuss\u00f5es sobre a precariza\u00e7\u00e3o do trabalho, envolvendo as empresas de aplicativos e as reinvindica\u00e7\u00f5es de entregadores. Ademais, cabe destacar que no per\u00edodo de pandemia h\u00e1 muitas mudan\u00e7as como, por exemplo, o uso de teletrabalho e flexibiliza\u00e7\u00f5es.<\/p>\n<p><b>7. O uso de Tecnologias em nosso dia a dia<\/b><\/p>\n<p><b><\/b><b><\/b>Cada vez mais a internet e as Tecnologias da Informa\u00e7\u00e3o e da Comunica\u00e7\u00e3o (TICs) ganham espa\u00e7o em nosso cotidiano. Se por um lado h\u00e1 vantagens ,tais como: acesso \u00e0 informa\u00e7\u00e3o e democratiza\u00e7\u00e3o do conhecimento, por outro lado \u00e9 necess\u00e1rio analisar criticamente, uma vez que as tecnologias podem agravar a perda e o controle da individualidade e da privacidade (tudo \u00e9 comunicado nas redes sociais). Outrossim, v\u00e1rias pesquisas apontam que h\u00e1 uma rela\u00e7\u00e3o direta do uso de tecnologias e o aumento da ansiedade, estresse e solid\u00e3o. Outro fator \u00e9 que o par\u00e2metro de felicidade passa a ser o n\u00famero de amigos virtuais e de curtidas em postagens.<\/p>\n<p><b>8. \u00cdndios<\/b><\/p>\n<p><b><\/b><b><\/b>Outro debate em evid\u00eancia s\u00e3o as quest\u00f5es ind\u00edgenas. Estes lutam por manter as suas reservas, costumes e tradi\u00e7\u00f5es. Por outro lado, a bancada ruralista no Congresso Nacional defende o fim de novas reservas e o uso de terras ind\u00edgenas para atender aos interesses do agroneg\u00f3cio e a explora\u00e7\u00e3o de recursos minerais.<\/p>\n<p>Autores como Darcy Ribeiro e Ailton Krenak s\u00e3o essenciais para uma boa fundamenta\u00e7\u00e3o de argumentos consistentes sobre o assunto.<\/p>\n<p>9<b>. Racismo<\/b><\/p>\n<p><b><\/b>A discrimina\u00e7\u00e3o racial no Brasil est\u00e1 diretamente associado ao racismo estrutural, que se inicia com a institui\u00e7\u00e3o da escravid\u00e3o no Brasil. \u00c9 fato que os negros n\u00e3o foram inclu\u00eddos na sociedade ap\u00f3s a aboli\u00e7\u00e3o e que o mito da democracia racial, engendrado pelo antrop\u00f3logo Gilberto Freyre, s\u00e3o fatores importantes para entender a viol\u00eancia contra a popula\u00e7\u00e3o negra, marcada por preconceitos, humilha\u00e7\u00f5es sociais e viol\u00eancia. Opera\u00e7\u00f5es desastrosas de \u00f3rg\u00e3os da seguran\u00e7a p\u00fablica (viol\u00eancia institucional) colocam este tema em evid\u00eancia &#8211; veja o caso Floyd nos EUA e suas repercuss\u00f5es em diversos pa\u00edses.<\/p>\n<p>10.\u00a0<strong>Educa\u00e7\u00e3o no Brasil<\/strong><\/p>\n<p>Infelizmente, os resultados da educa\u00e7\u00e3o brasileira s\u00e3o bens ruins &#8211; as avalia\u00e7\u00f5es nacionais e internacionais mostram isso: nossos estudantes possuem dificuldades de interpreta\u00e7\u00e3o e de abstra\u00e7\u00e3o. Assim, ficam alguns desafios:\u00a0 s\u00e3o necess\u00e1rias novas metodologias para ensinar e aprender, valoriza\u00e7\u00e3o dos profissionais, aumento de investimentos, diminui\u00e7\u00e3o das desigualdades socioecon\u00f4micas, etc.<\/p>\n<p>No contexto de pandemia, fica not\u00f3rio as desigualdades educacionais, uma vez que a maioria dos alunos de escolas p\u00fablicas n\u00e3o possuem acesso \u00e0 internet e \u00e0s tecnologias necess\u00e1rias para continuarem seus estudos. J\u00e1 os alunos de escolas privadas, rapidamente, tiverem assegurados a continuidade dos estudos, o que agrava ainda mais as disparidades.<\/p>\n<p><b>Quem sou eu?<\/b><\/p>\n<p><b><\/b>Sou o Professor Raphael Reis. Para quem ainda n\u00e3o me conhece, fica aqui uma breve apresenta\u00e7\u00e3o: sou Professor do Estrat\u00e9gia Concursos desde 2016 e leciono os seguintes conte\u00fados: Reda\u00e7\u00e3o (macroestrutura), Hist\u00f3ria, Filosofia e Sociologia. Fiz minha gradua\u00e7\u00e3o em Hist\u00f3ria (UFJF), especializa\u00e7\u00e3o em Pol\u00edticas P\u00fablicas e Gest\u00e3o Social (UFJF) e mestrado em Sociologia da Educa\u00e7\u00e3o (UFJF).<\/p>\n<p>Nos \u00faltimos anos tenho me especializado na parte de macroestrutura da<br \/>reda\u00e7\u00e3o. Ao perceber que a grande dificuldade dos candidatos \u00e9 desenvolver argumentos bem fundamentados, criei o curso in\u00e9dito e inovador de <a href=\"https:\/\/www.estrategiaconcursos.com.br\/curso\/ciencias-humanas-para-redacao-2020\/\">Ci\u00eancias Humanas para Reda\u00e7\u00e3o<\/a>, que j\u00e1 atendeu milhares de alunos e t\u00eam contribu\u00eddo decisivamente para a melhoria das notas. Sou autor do e-book <span style=\"float: none; background-color: #ffffff; color: #191e23; font-family: 'Noto Serif'; font-size: inherit; font-style: normal; font-variant: normal; font-weight: 400; letter-spacing: normal; line-height: inherit; text-align: left; text-decoration: none; text-indent: 0px; text-transform: none;\">best-seller <\/span>25 conceitos para usar na reda\u00e7\u00e3o<span style=\"float: none; background-color: #ffffff; color: #191e23; font-family: 'Noto Serif'; font-size: inherit; font-style: normal; font-variant: normal; font-weight: 400; letter-spacing: normal; line-height: inherit; text-align: left; text-decoration: none; text-indent: 0px; text-transform: none;\"> e editor da revista de atualidades Centro do Mundo.<\/span><\/p>\n<p><strong>Sigam-me os bons:<\/strong><\/p>\n\n\n<p>YouTube: <a href=\"https:\/\/www.youtube.com\/user\/donraphaelreis25\/\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">Professor Raphael Reis<\/a><\/p>\n\n\n\n<p>Telegram: <a href=\"https:\/\/t.me\/profrapha\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">profrapha<\/a> e <a href=\"https:\/\/t.me\/discursivasparaconcursos\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">discursivasparaconcursos<\/a><\/p>\n\n\n\n<p>Instagram: <a href=\"https:\/\/www.instagram.com\/profraphaelreis\/\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">@profraphaelreis<\/a><\/p>\n\n\n\n<p>Site: professorraphaelreis.com.br<\/p>\n\n\n\n<p><a href=\"https:\/\/docs.google.com\/forms\/d\/e\/1FAIpQLSeqQiPrGANvPQjt8ZTkqaZL96dgz8HnA6EHGHJlE2B9hXAghA\/viewform\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">Lista de E-mail<\/a><\/p>\n\n\n<p><strong>Quer receber materiais gratuitos e avisos de aul\u00f5es?<\/strong><\/p>\n<p>Acompanhe tamb\u00e9m os principais <a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-abertos\/\">concursos abertos no pa\u00eds<\/a>.<\/p>","protected":false},"excerpt":{"rendered":"<p>Prof. Rapha chegando na \u00e1rea para trazer uma lista atualizada de temas de reda\u00e7\u00e3o para concursos p\u00fablicos 2020. 1. Saneamento B\u00e1sico: Saneamento b\u00e1sico est\u00e1 na agenda das pol\u00edticas p\u00fablicas do Brasil. Essa problem\u00e1tica envolve princ\u00edpios b\u00e1sicos de cidadania e afeta diretamente a sa\u00fade p\u00fablica. Infelizmente, o acesso \u00e0 agua tratada n\u00e3o \u00e9 universal em boa [&hellip;]<\/p>\n","protected":false},"author":384,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"post_tipo":"article","footnotes":""},"categories":[1],"tags":[2773,2557,2846,2089,2772,2901],"tax_estado":[],"class_list":["post-87650","post","type-post","status-publish","format-standard","hentry","category-cursos-e-concursos","tag-conceitos-para-a-redacao","tag-provas-discursivas","tag-redacao-concursos-publicos","tag-redacao-enem","tag-redacao-vestibulares","tag-temas-para-redacao"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.2 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Temas de reda\u00e7\u00e3o para Concursos P\u00fablicos - 2020<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/temas-de-redacao-para-voce-treinar\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Temas de reda\u00e7\u00e3o para Concursos P\u00fablicos - 2020\" \/>\n<meta property=\"og:description\" content=\"Prof. Rapha chegando na \u00e1rea para trazer uma lista atualizada de temas de reda\u00e7\u00e3o para concursos p\u00fablicos 2020. 1. Saneamento B\u00e1sico: Saneamento b\u00e1sico est\u00e1 na agenda das pol\u00edticas p\u00fablicas do Brasil. Essa problem\u00e1tica envolve princ\u00edpios b\u00e1sicos de cidadania e afeta diretamente a sa\u00fade p\u00fablica. Infelizmente, o acesso \u00e0 agua tratada n\u00e3o \u00e9 universal em boa [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/temas-de-redacao-para-voce-treinar\/\" \/>\n<meta property=\"og:site_name\" content=\"Estrat\u00e9gia Concursos\" \/>\n<meta property=\"article:published_time\" content=\"2020-07-23T01:30:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-10-13T13:10:51+00:00\" \/>\n<meta name=\"author\" content=\"Raphael de Oliveira Reis\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:site\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Raphael de Oliveira Reis\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/temas-de-redacao-para-voce-treinar\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/temas-de-redacao-para-voce-treinar\/\"},\"author\":{\"name\":\"Raphael de Oliveira Reis\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/b49a1a49e5ef8a9f8d3268e74404a911\"},\"headline\":\"Temas de reda\u00e7\u00e3o para Concursos P\u00fablicos &#8211; 2020\",\"datePublished\":\"2020-07-23T01:30:00+00:00\",\"dateModified\":\"2022-10-13T13:10:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/temas-de-redacao-para-voce-treinar\/\"},\"wordCount\":1235,\"commentCount\":231,\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"keywords\":[\"Conceitos para a reda\u00e7\u00e3o\",\"provas discursivas\",\"Reda\u00e7\u00e3o Concursos P\u00fablicos\",\"REDA\u00c7\u00c3O ENEM\",\"Reda\u00e7\u00e3o Vestibulares\",\"Temas para reda\u00e7\u00e3o\"],\"articleSection\":[\"Concursos P\u00fablicos\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/temas-de-redacao-para-voce-treinar\/#respond\"]}],\"copyrightYear\":\"2020\",\"copyrightHolder\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/temas-de-redacao-para-voce-treinar\/\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/temas-de-redacao-para-voce-treinar\/\",\"name\":\"Temas de reda\u00e7\u00e3o para Concursos P\u00fablicos - 2020\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\"},\"datePublished\":\"2020-07-23T01:30:00+00:00\",\"dateModified\":\"2022-10-13T13:10:51+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/temas-de-redacao-para-voce-treinar\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/temas-de-redacao-para-voce-treinar\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/temas-de-redacao-para-voce-treinar\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Temas de reda\u00e7\u00e3o para Concursos P\u00fablicos &#8211; 2020\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"name\":\"Estrat\u00e9gia Concursos\",\"description\":\"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.\",\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\",\"name\":\"Estrat\u00e9gia Concursos\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"width\":230,\"height\":60,\"caption\":\"Estrat\u00e9gia Concursos\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/EstratConcursos\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/b49a1a49e5ef8a9f8d3268e74404a911\",\"name\":\"Raphael de Oliveira Reis\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/b1c5789180fc7bfb5103ec006c301370c02393e37aa13c55f6d72f05fcc76b3b?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/b1c5789180fc7bfb5103ec006c301370c02393e37aa13c55f6d72f05fcc76b3b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/b1c5789180fc7bfb5103ec006c301370c02393e37aa13c55f6d72f05fcc76b3b?s=96&d=mm&r=g\",\"caption\":\"Raphael de Oliveira Reis\"},\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/profraphaelreisgmail-com\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Temas de reda\u00e7\u00e3o para Concursos P\u00fablicos - 2020","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.estrategiaconcursos.com.br\/blog\/temas-de-redacao-para-voce-treinar\/","og_locale":"pt_BR","og_type":"article","og_title":"Temas de reda\u00e7\u00e3o para Concursos P\u00fablicos - 2020","og_description":"Prof. Rapha chegando na \u00e1rea para trazer uma lista atualizada de temas de reda\u00e7\u00e3o para concursos p\u00fablicos 2020. 1. Saneamento B\u00e1sico: Saneamento b\u00e1sico est\u00e1 na agenda das pol\u00edticas p\u00fablicas do Brasil. Essa problem\u00e1tica envolve princ\u00edpios b\u00e1sicos de cidadania e afeta diretamente a sa\u00fade p\u00fablica. Infelizmente, o acesso \u00e0 agua tratada n\u00e3o \u00e9 universal em boa [&hellip;]","og_url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/temas-de-redacao-para-voce-treinar\/","og_site_name":"Estrat\u00e9gia Concursos","article_published_time":"2020-07-23T01:30:00+00:00","article_modified_time":"2022-10-13T13:10:51+00:00","author":"Raphael de Oliveira Reis","twitter_card":"summary_large_image","twitter_creator":"@EstratConcursos","twitter_site":"@EstratConcursos","twitter_misc":{"Escrito por":"Raphael de Oliveira Reis","Est. tempo de leitura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/temas-de-redacao-para-voce-treinar\/#article","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/temas-de-redacao-para-voce-treinar\/"},"author":{"name":"Raphael de Oliveira Reis","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/b49a1a49e5ef8a9f8d3268e74404a911"},"headline":"Temas de reda\u00e7\u00e3o para Concursos P\u00fablicos &#8211; 2020","datePublished":"2020-07-23T01:30:00+00:00","dateModified":"2022-10-13T13:10:51+00:00","mainEntityOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/temas-de-redacao-para-voce-treinar\/"},"wordCount":1235,"commentCount":231,"publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"keywords":["Conceitos para a reda\u00e7\u00e3o","provas discursivas","Reda\u00e7\u00e3o Concursos P\u00fablicos","REDA\u00c7\u00c3O ENEM","Reda\u00e7\u00e3o Vestibulares","Temas para reda\u00e7\u00e3o"],"articleSection":["Concursos P\u00fablicos"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/temas-de-redacao-para-voce-treinar\/#respond"]}],"copyrightYear":"2020","copyrightHolder":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/temas-de-redacao-para-voce-treinar\/","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/temas-de-redacao-para-voce-treinar\/","name":"Temas de reda\u00e7\u00e3o para Concursos P\u00fablicos - 2020","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website"},"datePublished":"2020-07-23T01:30:00+00:00","dateModified":"2022-10-13T13:10:51+00:00","breadcrumb":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/temas-de-redacao-para-voce-treinar\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/temas-de-redacao-para-voce-treinar\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/temas-de-redacao-para-voce-treinar\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.estrategiaconcursos.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Temas de reda\u00e7\u00e3o para Concursos P\u00fablicos &#8211; 2020"}]},{"@type":"WebSite","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","name":"Estrat\u00e9gia Concursos","description":"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.","publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization","name":"Estrat\u00e9gia Concursos","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","width":230,"height":60,"caption":"Estrat\u00e9gia Concursos"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/EstratConcursos"]},{"@type":"Person","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/b49a1a49e5ef8a9f8d3268e74404a911","name":"Raphael de Oliveira Reis","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/b1c5789180fc7bfb5103ec006c301370c02393e37aa13c55f6d72f05fcc76b3b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b1c5789180fc7bfb5103ec006c301370c02393e37aa13c55f6d72f05fcc76b3b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b1c5789180fc7bfb5103ec006c301370c02393e37aa13c55f6d72f05fcc76b3b?s=96&d=mm&r=g","caption":"Raphael de Oliveira Reis"},"url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/profraphaelreisgmail-com\/"}]}},"_links":{"self":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/87650","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/users\/384"}],"replies":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/comments?post=87650"}],"version-history":[{"count":25,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/87650\/revisions"}],"predecessor-version":[{"id":1109293,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/87650\/revisions\/1109293"}],"wp:attachment":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media?parent=87650"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/categories?post=87650"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tags?post=87650"},{"taxonomy":"tax_estado","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tax_estado?post=87650"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}