{"id":851011,"date":"2021-09-22T09:12:00","date_gmt":"2021-09-22T12:12:00","guid":{"rendered":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?p=851011"},"modified":"2021-09-22T14:09:52","modified_gmt":"2021-09-22T17:09:52","slug":"raio-x-do-icms-o-minimo-que-voce-precisa-saber","status":"publish","type":"post","link":"https:\/\/www.estrategiaconcursos.com.br\/blog\/raio-x-do-icms-o-minimo-que-voce-precisa-saber\/","title":{"rendered":"Raio x do ICMS &#8211; O m\u00ednimo que voc\u00ea precisa saber para o xeque-mate"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"aligncenter is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/09\/08230543\/xadrez-1024x683.jpg\" alt=\"Xeque-mate no ICMS\" class=\"wp-image-856964\" width=\"531\" height=\"354\" srcset=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/09\/08230543\/xadrez-1024x683.jpg 1024w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/09\/08230543\/xadrez-300x200.jpg 300w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/09\/08230543\/xadrez-768x512.jpg 768w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/09\/08230543\/xadrez-610x407.jpg 610w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/09\/08230543\/xadrez.jpg 1062w\" sizes=\"auto, (max-width: 531px) 100vw, 531px\" \/><figcaption>Dando o Xeque-mate na banca!<\/figcaption><\/figure><\/div>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-vis-o-geral-sum-rio-do-raio-x-do-icms\">VIS\u00c3O GERAL &#8211; SUM\u00c1RIO DO RAIO X DO ICMS<\/h2>\n\n\n\n<p>Nossa inten\u00e7\u00e3o \u00e9 esclarecer pontos que, por vezes, s\u00e3o apenas decorados, bem como abastec\u00ea-los com um breve resumo, mas de qualidade, que possibilite uma \u201cpassada\u201d pelos principais pontos da mat\u00e9ria. Um verdadeiro &#8220;Raio X do ICMS b\u00e1sico para os fiscos&#8221;.<\/p>\n\n\n\n<p>Neste ano, h\u00e1 grandes expectativas de concursos para os Fiscos Estaduais. E o conhecimento desse Raio x do ICMS, com certeza, \u00e9 de grande import\u00e2ncia para seu sucesso!<\/p>\n\n\n\n<p>Observemos os pontos de estudo de hoje:<\/p>\n\n\n\n<ol class=\"wp-block-list\"><li>Defini\u00e7\u00e3o Geral;<\/li><li>Fun\u00e7\u00e3o do imposto;<\/li><li>Conceito de mercadoria;<\/li><li>Servi\u00e7os Tributados pelo ICMS;<\/li><li>Seletividade;<\/li><li>N\u00e3o-cumulatividade;<\/li><li>ICMS nas opera\u00e7\u00f5es interestaduais;<\/li><li>ICMS nas importa\u00e7\u00f5es;<\/li><li>Tributa\u00e7\u00e3o conjunta = ICMS x ISS;<\/li><li>Imunidades;<\/li><li>Concess\u00e3o de Benef\u00edcios Fiscais;<\/li><li>Quadro Geral ICMS.<\/li><\/ol>\n\n\n\n<p>Vamos come\u00e7ar!!<\/p>\n\n\n\n<p>O ICMS trata-se de um imposto previsto na Constitui\u00e7\u00e3o Federal, no seu art. 155, II, cuja compet\u00eancia para institui\u00e7\u00e3o foi atribu\u00edda aos estados e ao Distrito Federal.<\/p>\n\n\n\n<p>Nesse sentido, esse tributo \u00e9 o de maior arrecada\u00e7\u00e3o no Brasil e provoca a \u201cfamosa\u201d guerra fiscal entre os entes tributantes.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Fun\u00e7\u00e3o do Imposto<\/strong><\/h2>\n\n\n\n<p>Al\u00e9m disso, o ICMS tem finalidade, sem d\u00favida, <strong>fiscal<\/strong>. Ou seja, \u201carrancar o dinheiro do bolso \u00e9 a meta\u201d.<\/p>\n\n\n\n<p>Entretanto, a nossa Constitui\u00e7\u00e3o possibilita que o ICMS seja seletivo, em fun\u00e7\u00e3o da essencialidade das mercadorias e dos servi\u00e7os (CF, art. 155, \u00a72\u00b0, III). <\/p>\n\n\n\n<p>De forma que h\u00e1 possibilidade de um car\u00e1ter <strong>extrafiscal <\/strong>ao imposto. Em outras palavras, \u201carrancar o dinheiro do bolso pode ser secund\u00e1rio\u201d, confira:<\/p>\n\n\n\n<p>\u201cIII &#8211;<strong> poder\u00e1 <\/strong>ser seletivo, em fun\u00e7\u00e3o da essencialidade das mercadorias e dos servi\u00e7os;\u201d&nbsp;&nbsp;<\/p>\n\n\n\n<p><strong>Pessoal, cuidado com esse destaque! Alerta de pegadinha velha, mas eficaz das bancas<\/strong>.<\/p>\n\n\n\n<p>Isso porque para o IPI a seletividade \u00e9 obrigat\u00f3ria (CF, art. 153, \u00a73\u00b0, I):<\/p>\n\n\n\n<p><\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>\u00a7 3\u00ba O imposto previsto no inciso IV:<\/p><p>I &#8211; <strong>ser\u00e1 <\/strong>seletivo, em fun\u00e7\u00e3o da essencialidade do produto;<\/p><\/blockquote>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Conceito de Mercadoria<\/strong><\/h2>\n\n\n\n<p>Esse conceito \u00e9 importante para que possamos enquadrar o Raio x do ICMS.&nbsp;<\/p>\n\n\n\n<p>Assim, nas li\u00e7\u00f5es de Souto Maior Borges:<\/p>\n\n\n\n<p>\u201cMercadoria \u00e9 um <strong>bem m\u00f3vel <\/strong>que est\u00e1 no mundo dos neg\u00f3cios com <strong>finalidade comercial.\u201d<\/strong><\/p>\n\n\n\n<p>Al\u00e9m disso, o conceito de mercadoria tamb\u00e9m engloba os <strong>bens corp\u00f3reos e incorp\u00f3reos.<\/strong>&nbsp;<\/p>\n\n\n\n<p>Nessa linha, o Supremo Tribunal Federal entendeu que o ICMS incide sobre a comercializa\u00e7\u00e3o de software. Mesmo quando a aquisi\u00e7\u00e3o \u00e9 feita mediante transfer\u00eancia eletr\u00f4nica de dados (download de um site, por exemplo).<\/p>\n\n\n\n<p>O aluno mais atento nessa hora pergunta: \u201co que seria essa finalidade comercial? Isso \u00e9 muito amplo!\u201d. Por isso, faremos um pequeno voo ao art. 4\u00b0 da LC 87\/1996, que coloca como contribuinte do imposto:&nbsp;<\/p>\n\n\n\n<p>\u201cQualquer pessoa, f\u00edsica ou jur\u00eddica, que realize, <strong>com habitualidade<\/strong> ou <strong>em volume que caracterize intuito comercial<\/strong>, opera\u00e7\u00f5es de circula\u00e7\u00e3o de mercadoria ou presta\u00e7\u00f5es de servi\u00e7os de transporte interestadual e intermunicipal e de comunica\u00e7\u00e3o, ainda que as opera\u00e7\u00f5es e as presta\u00e7\u00f5es se iniciem no exterior.\u201d<\/p>\n\n\n\n<p>Assim, a <strong>habitualidade <\/strong>tem rela\u00e7\u00e3o com outros elementos que podem ser aferidos, como receita, custo, destino dos recursos, habitualidade de outras eventuais opera\u00e7\u00f5es, etc<\/p>\n\n\n\n<p>Por outro lado, o \u201c<strong>volume que caracteriza intuito comercial\u201d<\/strong> representa uma forma de \u201cpegar\u201d grandes opera\u00e7\u00f5es, que por falta de habitualidade, estariam fora do campo de incid\u00eancia do nosso ICMS.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-exemplificando\">Exemplificando<\/h3>\n\n\n\n<p>De in\u00edcio, imaginem, por exemplo, se a &#8220;Coca-Cola&#8221; observasse uma oportunidade de investimento na compra e posterior venda de todos os autom\u00f3veis de uma grande concession\u00e1ria.&nbsp;<\/p>\n\n\n\n<p>Seria justo que ela recebesse o mesmo tratamento tribut\u00e1rio que n\u00f3s, reles mortais, recebemos ao vender o nosso \u201ccaidinho\u201d? Penso que n\u00e3o e a legisla\u00e7\u00e3o tamb\u00e9m.<\/p>\n\n\n\n<p>Nessa opera\u00e7\u00e3o, mesmo sendo realizada num \u00fanico dia, acaba por ocorrer num <strong>volume <\/strong>que demonstra a presen\u00e7a de intuito comercial.<\/p>\n\n\n\n<p>De outro ponto, se a \u201cCoca-Cola\u201d vende seus computadores velhos para adquirir novos, n\u00e3o haver\u00e1 incid\u00eancia do ICMS sobre essa venda espor\u00e1dica. Pois n\u00e3o se trata da atividade-fim da entidade e claramente n\u00e3o h\u00e1 \u00e2nimo de lucro. <\/p>\n\n\n\n<p>Assim, a \u201cCoca-Cola\u201d se equipara a um<strong> alienante comum. <\/strong>Nessa linha \u00e9 a jurisprud\u00eancia do STF (RE 196.339).<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Servi\u00e7os tributados pelo ICMS<\/strong><\/h2>\n\n\n\n<p>O art. 2\u00b0 da LC 87\/96 nos traz:<\/p>\n\n\n\n<p>\u201cII &#8211; presta\u00e7\u00f5es de servi\u00e7os de transporte <strong>interestadual e intermunicipal<\/strong>, por qualquer via, de pessoas, bens, mercadorias ou valores;<\/p>\n\n\n\n<p>III &#8211; presta\u00e7\u00f5es onerosas de servi\u00e7os <strong>de comunica\u00e7\u00e3o, por qualquer meio,<\/strong> inclusive a gera\u00e7\u00e3o, a emiss\u00e3o, a recep\u00e7\u00e3o, a transmiss\u00e3o, a retransmiss\u00e3o, a repeti\u00e7\u00e3o e a amplia\u00e7\u00e3o de comunica\u00e7\u00e3o de qualquer natureza;\u201d<\/p>\n\n\n\n<p>Quanto ao servi\u00e7o de transporte, devemos ficar atentos ao transporte <strong>municipal, <\/strong>que \u00e9 objeto do imposto sobre servi\u00e7os de qualquer natureza -ISS &#8211; dos munic\u00edpios.<\/p>\n\n\n\n<p>J\u00e1 o servi\u00e7o de comunica\u00e7\u00e3o possui algumas caracter\u00edsticas especiais trazidas pelas cortes:<\/p>\n\n\n\n<ol class=\"wp-block-list\"><li>O ICMS n\u00e3o incide no servi\u00e7o dos provedores de acesso \u00e0 internet (s\u00famula 334, STJ);<\/li><li>O ICMS n\u00e3o incide sobre o servi\u00e7o de habilita\u00e7\u00e3o de telefone celular (s\u00famula 350, STJ).<\/li><\/ol>\n\n\n\n<p>Dessa forma, para as nossas cortes, essas atividades meio, de suporte, n\u00e3o se enquadram nos servi\u00e7os de comunica\u00e7\u00e3o.<\/p>\n\n\n\n<p>Por fim, apenas a transmiss\u00e3o <strong>onerosa <\/strong>est\u00e1 no campo de incid\u00eancia do ICMS. <\/p>\n\n\n\n<p>Isso porque h\u00e1 imunidade \u00e0s transmiss\u00f5es de recep\u00e7\u00e3o livre e gratuita (r\u00e1dio e TV abertas), nos termos da Constitui\u00e7\u00e3o Federal de 1988, al\u00ednea d do inciso X do \u00a72\u00b0 do art. 155.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Seletividade<\/strong><\/h2>\n\n\n\n<p>Como destaquei na FUN\u00c7\u00c3O PREDOMINANTE, a seletividade \u00e9 uma op\u00e7\u00e3o para o ICMS.<\/p>\n\n\n\n<p>De modo simples, a seletividade \u00e9 uma forma de diferenciar o impacto do imposto conforme a essencialidade do bem.<\/p>\n\n\n\n<p>Nessa l\u00f3gica, os bens consumidos por todas as classes sociais devem receber um menor impacto (arroz, feij\u00e3o). Ao contr\u00e1rio daqueles bens consumidos principalmente pelas pessoas de maior capacidade contributiva (ve\u00edculos).&nbsp;<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Raio X do ICMS e a <strong>N\u00e3o cumulatividade<\/strong><\/h2>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignleft size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/09\/12142916\/hungry-student-opens-mouth-widely-while-sees-delicious-slice-of-pizza-wants-to-eat-dressed-in-white-shirt-models-against-yellow-wall-positive-woman-with-junk-food-people-and-eating-1024x683.jpg\" alt=\"Raio-X do ICMS cumulativo\" class=\"wp-image-859320\" width=\"385\" height=\"257\" srcset=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/09\/12142916\/hungry-student-opens-mouth-widely-while-sees-delicious-slice-of-pizza-wants-to-eat-dressed-in-white-shirt-models-against-yellow-wall-positive-woman-with-junk-food-people-and-eating-1024x683.jpg 1024w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/09\/12142916\/hungry-student-opens-mouth-widely-while-sees-delicious-slice-of-pizza-wants-to-eat-dressed-in-white-shirt-models-against-yellow-wall-positive-woman-with-junk-food-people-and-eating-300x200.jpg 300w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/09\/12142916\/hungry-student-opens-mouth-widely-while-sees-delicious-slice-of-pizza-wants-to-eat-dressed-in-white-shirt-models-against-yellow-wall-positive-woman-with-junk-food-people-and-eating-768x512.jpg 768w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/09\/12142916\/hungry-student-opens-mouth-widely-while-sees-delicious-slice-of-pizza-wants-to-eat-dressed-in-white-shirt-models-against-yellow-wall-positive-woman-with-junk-food-people-and-eating-1536x1024.jpg 1536w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/09\/12142916\/hungry-student-opens-mouth-widely-while-sees-delicious-slice-of-pizza-wants-to-eat-dressed-in-white-shirt-models-against-yellow-wall-positive-woman-with-junk-food-people-and-eating-2048x1365.jpg 2048w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/09\/12142916\/hungry-student-opens-mouth-widely-while-sees-delicious-slice-of-pizza-wants-to-eat-dressed-in-white-shirt-models-against-yellow-wall-positive-woman-with-junk-food-people-and-eating-610x407.jpg 610w\" sizes=\"auto, (max-width: 385px) 100vw, 385px\" \/><figcaption>Raio-X do ICMS: Nos tributos cumulativos, a &#8220;fome&#8221; do Estado \u00e9 maior!<\/figcaption><\/figure><\/div>\n\n\n\n<p>Prevista no art. 155, \u00a72\u00b0, I:<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>\u201c\u00a7 2\u00ba O imposto previsto no inciso II atender\u00e1 ao seguinte: &nbsp; &nbsp; &nbsp; &nbsp; <a href=\"http:\/\/www.planalto.gov.br\/ccivil_03\/constituicao\/Emendas\/Emc\/emc03.htm#art1\">(Reda\u00e7\u00e3o dada pela Emenda Constitucional n\u00ba 3, de 1993)<\/a><\/p><p>I &#8211; ser\u00e1 n\u00e3o-cumulativo, <strong>compensando-se o que for devido<\/strong> em cada opera\u00e7\u00e3o relativa \u00e0 circula\u00e7\u00e3o de mercadorias ou presta\u00e7\u00e3o de servi\u00e7os <strong>com o montante cobrado<\/strong> nas anteriores pelo mesmo ou outro Estado ou pelo Distrito Federal;\u201d<\/p><\/blockquote>\n\n\n\n<p>Como o ICMS \u00e9 plurif\u00e1sico (em regra, h\u00e1 v\u00e1rias incid\u00eancias at\u00e9 chegar ao seu consumidor final). Esse princ\u00edpio tem o objetivo de impedir que os efeitos tribut\u00e1rios sejam somados, tornando seu impacto \u201cimprevis\u00edvel\u201d.<\/p>\n\n\n\n<p>Como simples exemplo, vamos fazer um Raio x do ICMS nesse ponto =  imagine um produto com al\u00edquota de 10%, que cada contribuinte sempre acrescente uma margem de lucro de 50% do seu custo e no sistema <strong>cumulativo<\/strong>:<\/p>\n\n\n\n<p>Inicialmente, partindo da F\u00e1brica (venda = R$ 100,00 ; <strong>ICMS = R$ 10,00<\/strong>)\u27f6 Atacadista (Venda = R$ 150,00; <strong>ICMS = R$ 15,00)<\/strong>\u27f6 Consumidor Final<\/p>\n\n\n\n<p><em>Portanto, o total de ICMS ao longo da cadeia produtiva = R$10,00 + R$15,00 \u00e9 igual a<strong> R$25,00<\/strong><\/em>.<\/p>\n\n\n\n<p>Observem ainda que se a cadeia tiver um maior n\u00famero de compras e vendas, essa \u201cbola de neve\u201d ir\u00e1 crescer de forma assustadora.&nbsp;<\/p>\n\n\n\n<p>Por isso,&nbsp; neste nosso exemplo, segundo a <strong>n\u00e3o-cumulatividade<\/strong>:<\/p>\n\n\n\n<p><em>O ICMS da opera\u00e7\u00e3o ficaria = R$ 10,00 + (R$ 15,00 &#8211; R$ 10,00)= <strong>R$ 15,00.<\/strong><\/em><\/p>\n\n\n\n<p>Um detalhe muito importante \u00e9 a an\u00e1lise desse <strong>&#8220;montante cobrado nas opera\u00e7\u00f5es anteriores\u201d.<\/strong><\/p>\n\n\n\n<p>Isso significa que <strong>a dedu\u00e7\u00e3o independe do efetivo pagamento. Cuidado com isso!<\/strong><\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-para-nos-aproximarmos-do-xeque-mate\">Para nos aproximarmos do xeque-mate:<\/h3>\n\n\n\n<p>Vejamos outras disposi\u00e7\u00f5es aplic\u00e1veis \u00e0 n\u00e3o-cumulatividade:<\/p>\n\n\n\n<p>\u201cArt. 155, \u00a72\u00b0, II &#8211; a isen\u00e7\u00e3o ou n\u00e3o-incid\u00eancia, salvo determina\u00e7\u00e3o em contr\u00e1rio da legisla\u00e7\u00e3o:<\/p>\n\n\n\n<p>a) n\u00e3o implicar\u00e1 cr\u00e9dito para compensa\u00e7\u00e3o com o montante devido nas opera\u00e7\u00f5es ou presta\u00e7\u00f5es seguintes;<\/p>\n\n\n\n<p>b) acarretar\u00e1 a anula\u00e7\u00e3o do cr\u00e9dito relativo \u00e0s opera\u00e7\u00f5es anteriores;\u201d<\/p>\n\n\n\n<p>Uma an\u00e1lise simples, mas eficaz dos dispositivos, nos permite concluir que somente haver\u00e1 cr\u00e9dito a ser compensado nas opera\u00e7\u00f5es posteriores se houver obriga\u00e7\u00e3o de pagamento na opera\u00e7\u00e3o ou presta\u00e7\u00e3o.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>O RAIO X do ICMS nas opera\u00e7\u00f5es interestaduais<\/strong><\/h2>\n\n\n\n<p>Para que haja cr\u00e9dito, sem obriga\u00e7\u00e3o de pagamento, \u00e9 preciso disposi\u00e7\u00e3o expressa da legisla\u00e7\u00e3o.<\/p>\n\n\n\n<p>Como forma de evitar a \u201cguerra fiscal\u201d entres os estados e o DF, a al\u00edquota interestadual \u00e9 fixada pelo Senado Federal:<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>\u201cart. 155, \u00a72\u00b0, IV &#8211; resolu\u00e7\u00e3o do Senado Federal, de iniciativa do Presidente da Rep\u00fablica ou de um ter\u00e7o dos Senadores, aprovada pela maioria absoluta de seus membros,<strong> estabelecer\u00e1 as al\u00edquotas<\/strong> aplic\u00e1veis \u00e0s opera\u00e7\u00f5es e presta\u00e7\u00f5es, <strong>interestaduais <\/strong>e de exporta\u00e7\u00e3o;\u201d<\/p><\/blockquote>\n\n\n\n<p>Um ponto bastante explorado pelas bancas \u00e9 a divis\u00e3o do ICMS e a responsabilidade pelo recolhimento aos cofres p\u00fablicos. <\/p>\n\n\n\n<p>Assim, teremos (exceto para combust\u00edveis e lubrificantes de incid\u00eancia monof\u00e1sica\u2217, vide art. 155, \u00a74\u00b0):<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>&#8220;Art. 155, \u00a72\u00b0, VII &#8211; nas opera\u00e7\u00f5es e presta\u00e7\u00f5es que destinem bens e servi\u00e7os a consumidor final, contribuinte ou n\u00e3o do imposto, localizado em outro Estado, adotar-se-\u00e1 a al\u00edquota interestadual e caber\u00e1 ao Estado de localiza\u00e7\u00e3o do destinat\u00e1rio o imposto correspondente \u00e0 diferen\u00e7a entre a al\u00edquota interna do Estado destinat\u00e1rio e a al\u00edquota interestadual; &nbsp; \u201c<\/p><\/blockquote>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-desmembrando\">Desmembrando:<\/h3>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"402\" height=\"286\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/09\/08143813\/concordancia.png\" alt=\"Raio-X do ICMS nas opera\u00e7\u00f5es interestaduais\" class=\"wp-image-856473\" srcset=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/09\/08143813\/concordancia.png 402w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/09\/08143813\/concordancia-300x213.png 300w\" sizes=\"auto, (max-width: 402px) 100vw, 402px\" \/><figcaption>Raio-X do ICMS nas opera\u00e7\u00f5es interestaduais<\/figcaption><\/figure>\n\n\n\n<ul class=\"wp-block-list\"><li>A unidade da federa\u00e7\u00e3o de localiza\u00e7\u00e3o do <strong>remetente <\/strong>far\u00e1 jus ao valor da opera\u00e7\u00e3o, combinado com a <strong>al\u00edquota interestadual.<\/strong><\/li><li>J\u00e1 para<strong> <\/strong>o estado ou DF destinat\u00e1rio, deve-se analisar se a venda \u00e9 destinada a consumidor final ou n\u00e3o:<\/li><\/ul>\n\n\n\n<ol class=\"wp-block-list\"><li>Sendo <strong>consumidor final, contribuinte ou n\u00e3o<\/strong> = o ente far\u00e1 jus ao valor da opera\u00e7\u00e3o, combinada \u00e0 diferen\u00e7a entre sua al\u00edquota interna e a al\u00edquota interestadual (por exemplo = 18% &#8211; 12% \u00e9 igual a 6%).<\/li><li><strong>N\u00e3o sendo consumidor final<\/strong> = o ente destinat\u00e1rio da opera\u00e7\u00e3o n\u00e3o far\u00e1 jus a nenhum valor na opera\u00e7\u00e3o interestadual. J\u00e1 que ele ter\u00e1 a oportunidade de tributar a sa\u00edda futura da mercadoria pela sua al\u00edquota interna cheia, sem dedu\u00e7\u00e3o.<\/li><\/ol>\n\n\n\n<p>Quanto \u00e0 obriga\u00e7\u00e3o de recolhimento, a letra da Constitui\u00e7\u00e3o \u00e9 clara:<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>Art. 155, \u00a72\u00b0, VIII &#8211; a <strong>responsabilidade pelo recolhimento<\/strong> do imposto correspondente \u00e0 diferen\u00e7a entre a al\u00edquota interna e a interestadual de que trata o inciso VII ser\u00e1 atribu\u00edda:&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;<\/p><\/blockquote>\n\n\n\n<p>a) ao <strong>destinat\u00e1rio<\/strong> = quando <strong>este for contribuinte<\/strong> do imposto;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;<\/p>\n\n\n\n<p>b) ao <strong>remetente<\/strong> = quando o <strong>destinat\u00e1rio n\u00e3o for contribuinte<\/strong> do imposto;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>O RAIO-X do ICMS nas importa\u00e7\u00f5es<\/strong><\/h2>\n\n\n\n<p>Nas importa\u00e7\u00f5es, n\u00e3o h\u00e1 a necessidade de se avaliar habitualidade, volume ou finalidade da opera\u00e7\u00e3o.<\/p>\n\n\n\n<p>De modo simples e r\u00e1pido = importou, pagou!!<\/p>\n\n\n\n<p>Outro ponto de destaque, \u00e9 que o fato gerador ocorre por ocasi\u00e3o do <strong>Desembara\u00e7o aduaneiro.&nbsp;<\/strong><\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>STF &#8211; S\u00famula 661 &#8211; Na entrada de mercadoria importada do exterior, \u00e9 leg\u00edtima a cobran\u00e7a do ICMS por ocasi\u00e3o do desembara\u00e7o aduaneiro.<\/p><\/blockquote>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Tributa\u00e7\u00e3o Conjunta de mercadorias e servi\u00e7os<\/strong><\/h2>\n\n\n\n<p>A LC 116\/2003 cont\u00e9m a lista taxativa de servi\u00e7os presentes no campo de incid\u00eancia do ISS.&nbsp;<\/p>\n\n\n\n<p>Ainda, h\u00e1 servi\u00e7os que, pela sua natureza, compreendem a entrega de mercadorias.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-nesses-casos-a-regra-objetiva\">Nesses casos, a regra \u00e9 objetiva:<\/h3>\n\n\n\n<ol class=\"wp-block-list\"><li>N\u00e3o havendo men\u00e7\u00e3o ao ICMS na lei, o ISS incidir\u00e1 sobre tudo = servi\u00e7o + mercadoria;<\/li><li>Se houver indica\u00e7\u00e3o de incid\u00eancia do ICMS = O ICMS incidir\u00e1 sobre a mercadoria e o ISS sobre o servi\u00e7o.<\/li><li>Caso o servi\u00e7o n\u00e3o esteja na compet\u00eancia do munic\u00edpio. \u00c9 poss\u00edvel que o estado o tribute. Contato que essa presta\u00e7\u00e3o seja conjunta com o fornecimento de mercadorias. Inclusive este \u00e9 o entendimento das nossas cortes:<\/li><\/ol>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>STJ &#8211; S\u00famula 163 &#8211; \u201cO fornecimento de mercadorias com a simult\u00e2nea presta\u00e7\u00e3o de servi\u00e7os em bares, restaurantes e estabelecimentos similares constitui fato gerador do ICMS a incidir sobre o valor total da opera\u00e7\u00e3o\u201d<\/p><\/blockquote>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Imunidades (exporta\u00e7\u00f5es, outras)<\/strong><\/h2>\n\n\n\n<p>Como sabemos, imunidade \u00e9 uma forma de n\u00e3o-incid\u00eancia prevista na Constitui\u00e7\u00e3o.<\/p>\n\n\n\n<p>Por conseguinte, temos as seguintes imunidades do ICMS. Fora as demais imunidades pertinentes a todos os tributos:<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>\u201cArt. 155, \u00a72\u00b0, X &#8211; n\u00e3o incidir\u00e1:<\/p><p>a) sobre opera\u00e7\u00f5es que destinem mercadorias para o exterior, nem sobre servi\u00e7os prestados a destinat\u00e1rios no exterior, assegurada a manuten\u00e7\u00e3o e<strong> o aproveitamento do montante do imposto cobrado nas opera\u00e7\u00f5es e presta\u00e7\u00f5es anteriores;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;<\/strong><\/p><p>b) sobre opera\u00e7\u00f5es que destinem a outros Estados petr\u00f3leo, inclusive lubrificantes, combust\u00edveis l\u00edquidos e gasosos dele derivados, e energia el\u00e9trica;<\/p><p>c) sobre o ouro, nas hip\u00f3teses definidas no art. 153, \u00a7 5\u00ba;<\/p><p>d) nas presta\u00e7\u00f5es de servi\u00e7o de comunica\u00e7\u00e3o nas modalidades de radiodifus\u00e3o sonora e de sons e imagens de recep\u00e7\u00e3o livre e<strong> gratuita; \u201c<\/strong><\/p><\/blockquote>\n\n\n\n<p>Nas exporta\u00e7\u00f5es, devemos prestar aten\u00e7\u00e3o para o fato de que os cr\u00e9ditos cobrados na opera\u00e7\u00e3o anterior \u00e0 exporta\u00e7\u00e3o s\u00e3o mantidos. <\/p>\n\n\n\n<p>Essa \u00e9 uma importante exce\u00e7\u00e3o \u00e0 regrinha da n\u00e3o-cumulatividade, que determina a anula\u00e7\u00e3o ou que n\u00e3o haja cr\u00e9dito para os casos em que n\u00e3o h\u00e1 obriga\u00e7\u00e3o de pagamento.<\/p>\n\n\n\n<p>Ainda, a <strong>imunidade do petr\u00f3leo,<\/strong> prevista na al\u00ednea b, <strong>n\u00e3o se aplica<\/strong> aos combust\u00edveis e lubrificantes aos quais a LC define <strong>que incidem uma \u00fanica vez<\/strong> (ser\u00e1 monof\u00e1sica).<\/p>\n\n\n\n<p>Por outro lado, o ICMS n\u00e3o incide sobre o ouro quando for ativo financeiro ou instrumento cambial. Bem diferente daquele cord\u00e3o de ouro bonito, com cifr\u00e3o, vendido nas lojas, pois o ouro assume vi\u00e9s comercial. Ent\u00e3o, ICMS neles!<\/p>\n\n\n\n<p>Por fim, como mencionado acima, os servi\u00e7os de comunica\u00e7\u00e3o gratuitos est\u00e3o fora do campo de incid\u00eancia do ICMS.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Concess\u00e3o de benef\u00edcios fiscais de ICMS<\/strong><\/h2>\n\n\n\n<p>Ao cabo, como complemento do nosso Raio X do ICMS, a concess\u00e3o e a revoga\u00e7\u00e3o de benef\u00edcios fiscais de ICMS dependem. Como regra, de <strong>pr\u00e9via delibera\u00e7\u00e3o conjunta dos estados e do Distrito Federal<\/strong>. Conforme regulado em lei complementar (CF, art. 155, \u00a72\u00b0, XII, g).<\/p>\n\n\n\n<p>Assim, a LC 24\/75 faz esse papel. Fixando o regramento para os benef\u00edcios fiscais, que t\u00eam delibera\u00e7\u00e3o nas reuni\u00f5es do CONFAZ.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Quadro geral do Raio X do ICMS<\/strong><\/h2>\n\n\n\n<ol class=\"wp-block-list\"><li>Tributo indireto = repercuss\u00e3o econ\u00f4mica n\u00e3o \u00e9 sentida pelo contribuinte (comerciante). Mas sim, pelo consumidor final;<\/li><li>Plurif\u00e1sico = Ocorre v\u00e1rias vezes durante a cadeia produtiva, exceto o ICMS- monof\u00e1sico;<\/li><li>Princ\u00edpio da legalidade = Admite exce\u00e7\u00e3o para <strong>fixa\u00e7\u00e3o <\/strong>da al\u00edquota sobre <strong>combust\u00edveis <\/strong>definidos em LC como <strong>monof\u00e1sicos<\/strong>. J\u00e1 que ocorre por conv\u00eanio &#8211; CONFAZ;<\/li><li>Lan\u00e7amento = por homologa\u00e7\u00e3o;<\/li><li>Princ\u00edpio da anterioridade = exce\u00e7\u00e3o \u00e9 o <strong>restabelecimento <\/strong>das al\u00edquotas na incid\u00eancia <strong>monof\u00e1sica <\/strong>com <strong>combust\u00edveis<\/strong>;<\/li><li>Princ\u00edpio da noventena = Est\u00e1 sujeito;<\/li><li>Proporcional = al\u00edquota independe do valor da base de c\u00e1lculo;<\/li><li>Fiscal;<\/li><\/ol>\n\n\n\n<h2 class=\"wp-block-heading\">CONCLUS\u00c3O &#8211; Xeque-mate!<\/h2>\n\n\n\n<p>Espero que esse  Raio x do ICMS os ajude nessa empreitada de estudos. E que sirva como um bom lembrete de alguns pontos de aten\u00e7\u00e3o bastante cobrados.<\/p>\n\n\n\n<p>Al\u00e9m disso, deixamos muito claro que esse resumo \u00e9 focado na legisla\u00e7\u00e3o. N\u00e3o \u00e9 um estudo completo da mat\u00e9ria.<\/p>\n\n\n\n<p>Ressaltamos ainda que nem todos os artigos e par\u00e1grafos da legisla\u00e7\u00e3o est\u00e3o aqui. Trazemos apenas o que possui <a href=\"https:\/\/www.estrategiaconcursos.com.br\/professores\/\">maior cobran\u00e7a em provas.<\/a><\/p>\n\n\n\n<p>Ademais, o aluno deve procurar as <a href=\"https:\/\/www.estrategiaconcursos.com.br\/assinaturas\/\">aulas em PDF<\/a>. Nelas, o professor aborda a jurisprud\u00eancia e a doutrina associadas a cada um dos itens estudados. Apenas assim, o aluno consegue dominar a banca escolhida.<\/p>\n\n\n\n<p>Por fim, nos PDFs, existem quest\u00f5es de fixa\u00e7\u00e3o que aumentam muito a reten\u00e7\u00e3o dos assuntos estudados. Por esse motivo, refor\u00e7amos a import\u00e2ncia de um estudo completo por meio de PDFs, v\u00eddeo aulas, Passo Estrat\u00e9gico e Trilhas Estrat\u00e9gicas. Que apenas a<a href=\"https:\/\/www.estrategiaconcursos.com.br\/assinaturas\/\"> assinatura do Estrat\u00e9gia traz<\/a>.<\/p>\n\n\n\n<p>Um abra\u00e7o.<\/p>\n\n\n\n<p>Rodrigo Batalha<\/p>\n\n\n\n<p><a href=\"http:\/\/www.planalto.gov.br\/ccivil_03\/constituicao\/constituicao.htm\">http:\/\/www.planalto.gov.br\/ccivil_03\/constituicao\/constituicao.htm<\/a><\/p>\n\n\n\n<p>http:\/\/www.planalto.gov.br\/ccivil_03\/leis\/lcp\/lcp87.htm<\/p>\n\n\n\n<h2 class=\"has-text-align-center wp-block-heading\" id=\"h-cursos-e-assinaturas\">Cursos e Assinaturas<\/h2>\n\n\n\n<p>Prepare-se com o melhor material e com quem mais aprova em Concursos P\u00fablicos em todo o pa\u00eds!<\/p>\n\n\n\n<div class=\"container\" id=\"boxes\">\n  <div class=\"row\">\n    <div class=\"col-sm\">\n      <div class=\"estrategia\" id=\"box-assinatura\">\n        <h3 class=\"titulo-assinatura\">Assinatura de Concursos<\/h3>\n        <p class=\"subtitulo-assinatura\">Assinatura de 1 ano ou 2 anos<\/p>\n        <div class=\"box-botao\">\n          <a class=\"btn-assinatura\" target=\"_blank\" href=\"https:\/\/www.estrategiaconcursos.com.br\/assinaturas\/\" role=\"button\" rel=\"noopener noreferrer\">ASSINE AGORA<\/a>\n        <\/div>\n      <\/div>\n      <p class=\"texto-auxiliar\"><\/p>\n    <\/div>\n    <div class=\"col-sm\">\n      <div class=\"questoes\" id=\"box-assinatura\">\n        <h3 class=\"titulo-assinatura\">Sistema de Quest\u00f5es<\/h3>\n        <p class=\"subtitulo-assinatura\">Assinatura de 1 ano ou 2 anos\n<\/p>\n        <div class=\"box-botao\">\n          <a class=\"btn-assinatura\" target=\"_blank\" href=\"https:\/\/www.estrategiaconcursos.com.br\/cursosPorConcurso\/sistema-de-questoes\/#\/\" role=\"button\" rel=\"noopener noreferrer\">ASSINE AGORA<\/a>\n        <\/div>\n      <\/div>\n      <p class=\"texto-auxiliar\"><\/p>\n    <\/div>\n  <\/div>\n<\/div>\n\n\n\n<div class=\"container\" id=\"boxes\">\n  <div class=\"row\">\n\n    <div class=\"col-sm\" id=\"boxes-concursos\">\n      <div style=\"background-color: #005DAD;\" class=\"conteudo-concursos\" id=\"box-concursos\">\n        <h3 class=\"titulo-assinatura\">Concursos Abertos<\/h3>\n        <p class=\"subtitulo-assinatura\">mais de 15 mil vagas<\/p>\n        <div class=\"box-botao\">\n          <a class=\"btn-assinatura\" target=\"_blank\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-abertos\/\" role=\"button\" rel=\"noopener noreferrer\">Conhe\u00e7a Agora<\/a>\n        <\/div>\n      <\/div>\n    <\/div>\n\n    \n\n    <div class=\"col-sm\" id=\"boxes-concursos\">\n      <div style=\"background-color: #419FF0;\" class=\"conteudo-concursos\" id=\"box-concursos\">\n        <h3 class=\"titulo-assinatura\">Concursos 2021<\/h3>\n        <p class=\"subtitulo-assinatura\">mais de 17 mil vagas<\/p>\n        <div class=\"box-botao\">\n          <a class=\"btn-assinatura\" target=\"_blank\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-2021\/\" role=\"button\" rel=\"noopener noreferrer\">Conhe\u00e7a Agora<\/a>\n        <\/div>\n      <\/div>\n    <\/div>\n\n  <\/div>\n<\/div>\n\n\n\n<p>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>VIS\u00c3O GERAL &#8211; SUM\u00c1RIO DO RAIO X DO ICMS Nossa inten\u00e7\u00e3o \u00e9 esclarecer pontos que, por vezes, s\u00e3o apenas decorados, bem como abastec\u00ea-los com um breve resumo, mas de qualidade, que possibilite uma \u201cpassada\u201d pelos principais pontos da mat\u00e9ria. Um verdadeiro &#8220;Raio X do ICMS b\u00e1sico para os fiscos&#8221;. Neste ano, h\u00e1 grandes expectativas de [&hellip;]<\/p>\n","protected":false},"author":2202,"featured_media":862544,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"post_tipo":"article","footnotes":""},"categories":[1],"tags":[],"tax_estado":[219964,219965,219966,219967,219968,219969,219963,219970,219971,219972,219973,219974,219975,219976,219977,219978,219979,219980,219981,219982,219983,219984,219985,219986,219987,219988,219989,219990],"class_list":["post-851011","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cursos-e-concursos","tax_estado-ac","tax_estado-al","tax_estado-am","tax_estado-ap","tax_estado-ba","tax_estado-ce","tax_estado-concursos-federais","tax_estado-df","tax_estado-es","tax_estado-go","tax_estado-ma","tax_estado-mg","tax_estado-ms","tax_estado-mt","tax_estado-pa","tax_estado-pb","tax_estado-pe","tax_estado-pi","tax_estado-pr","tax_estado-rj","tax_estado-rn","tax_estado-ro","tax_estado-rr","tax_estado-rs","tax_estado-sc","tax_estado-se","tax_estado-sp","tax_estado-to"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.2 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Raio x do ICMS - O m\u00ednimo que voc\u00ea precisa saber para o xeque-mate<\/title>\n<meta name=\"description\" content=\"Fala Galera! Temos aqui o verdadeiro Raio X do ICMS, com aquela jogada de mestre para seu Xeque-mate nos concursos Fiscais!!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/raio-x-do-icms-o-minimo-que-voce-precisa-saber\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Raio x do ICMS - O m\u00ednimo que voc\u00ea precisa saber para o xeque-mate\" \/>\n<meta property=\"og:description\" content=\"Fala Galera! Temos aqui o verdadeiro Raio X do ICMS, com aquela jogada de mestre para seu Xeque-mate nos concursos Fiscais!!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/raio-x-do-icms-o-minimo-que-voce-precisa-saber\/\" \/>\n<meta property=\"og:site_name\" content=\"Estrat\u00e9gia Concursos\" \/>\n<meta property=\"article:published_time\" content=\"2021-09-22T12:12:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-09-22T17:09:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/09\/16110037\/xadrez-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1062\" \/>\n\t<meta property=\"og:image:height\" content=\"708\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Rodrigo Augusto Batalha Alves\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:site\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Rodrigo Augusto Batalha Alves\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"12 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/raio-x-do-icms-o-minimo-que-voce-precisa-saber\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/raio-x-do-icms-o-minimo-que-voce-precisa-saber\/\"},\"author\":{\"name\":\"Rodrigo Augusto Batalha Alves\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/aa0bf103f86069bff16b1ddfb510b18f\"},\"headline\":\"Raio x do ICMS &#8211; O m\u00ednimo que voc\u00ea precisa saber para o xeque-mate\",\"datePublished\":\"2021-09-22T12:12:00+00:00\",\"dateModified\":\"2021-09-22T17:09:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/raio-x-do-icms-o-minimo-que-voce-precisa-saber\/\"},\"wordCount\":2764,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/raio-x-do-icms-o-minimo-que-voce-precisa-saber\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/09\/16110037\/xadrez-1.jpg\",\"articleSection\":[\"Concursos P\u00fablicos\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/raio-x-do-icms-o-minimo-que-voce-precisa-saber\/#respond\"]}],\"copyrightYear\":\"2021\",\"copyrightHolder\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/raio-x-do-icms-o-minimo-que-voce-precisa-saber\/\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/raio-x-do-icms-o-minimo-que-voce-precisa-saber\/\",\"name\":\"Raio x do ICMS - O m\u00ednimo que voc\u00ea precisa saber para o xeque-mate\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/raio-x-do-icms-o-minimo-que-voce-precisa-saber\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/raio-x-do-icms-o-minimo-que-voce-precisa-saber\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/09\/16110037\/xadrez-1.jpg\",\"datePublished\":\"2021-09-22T12:12:00+00:00\",\"dateModified\":\"2021-09-22T17:09:52+00:00\",\"description\":\"Fala Galera! Temos aqui o verdadeiro Raio X do ICMS, com aquela jogada de mestre para seu Xeque-mate nos concursos Fiscais!!\",\"breadcrumb\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/raio-x-do-icms-o-minimo-que-voce-precisa-saber\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/raio-x-do-icms-o-minimo-que-voce-precisa-saber\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/raio-x-do-icms-o-minimo-que-voce-precisa-saber\/#primaryimage\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/09\/16110037\/xadrez-1.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/09\/16110037\/xadrez-1.jpg\",\"width\":1062,\"height\":708,\"caption\":\"Raio-X do ICMS\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/raio-x-do-icms-o-minimo-que-voce-precisa-saber\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Raio x do ICMS &#8211; O m\u00ednimo que voc\u00ea precisa saber para o xeque-mate\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"name\":\"Estrat\u00e9gia Concursos\",\"description\":\"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.\",\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\",\"name\":\"Estrat\u00e9gia Concursos\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"width\":230,\"height\":60,\"caption\":\"Estrat\u00e9gia Concursos\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/EstratConcursos\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/aa0bf103f86069bff16b1ddfb510b18f\",\"name\":\"Rodrigo Augusto Batalha Alves\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/54f78a13020d62df814fe30a9ecf7fac2702db4f0b5ec9af6f0bc06ea8f1c178?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/54f78a13020d62df814fe30a9ecf7fac2702db4f0b5ec9af6f0bc06ea8f1c178?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/54f78a13020d62df814fe30a9ecf7fac2702db4f0b5ec9af6f0bc06ea8f1c178?s=96&d=mm&r=g\",\"caption\":\"Rodrigo Augusto Batalha Alves\"},\"description\":\"Cargo Atual: Auditor Fiscal da Receita do Distrito Federal; Aprova\u00e7\u00f5es: SEFAZ DF, Analista de Controle Externo do TCE PE, TRE RJ, TRE SP, Ag\u00eancia Nacional de Minera\u00e7\u00e3o (ANM), Col\u00e9gio Naval; Mestre em Direito pela Universidade Cat\u00f3lica de Bras\u00edlia; P\u00f3s-graduado em Direito Tribut\u00e1rio e Direito Econ\u00f4mico e Financeiro Graduado em Ci\u00eancias Atuariais.\",\"sameAs\":[\"https:\/\/www.instagram.com\/rd.batalha\/\"],\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/robat07gmail-com\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Raio x do ICMS - O m\u00ednimo que voc\u00ea precisa saber para o xeque-mate","description":"Fala Galera! Temos aqui o verdadeiro Raio X do ICMS, com aquela jogada de mestre para seu Xeque-mate nos concursos Fiscais!!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.estrategiaconcursos.com.br\/blog\/raio-x-do-icms-o-minimo-que-voce-precisa-saber\/","og_locale":"pt_BR","og_type":"article","og_title":"Raio x do ICMS - O m\u00ednimo que voc\u00ea precisa saber para o xeque-mate","og_description":"Fala Galera! Temos aqui o verdadeiro Raio X do ICMS, com aquela jogada de mestre para seu Xeque-mate nos concursos Fiscais!!","og_url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/raio-x-do-icms-o-minimo-que-voce-precisa-saber\/","og_site_name":"Estrat\u00e9gia Concursos","article_published_time":"2021-09-22T12:12:00+00:00","article_modified_time":"2021-09-22T17:09:52+00:00","og_image":[{"width":1062,"height":708,"url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/09\/16110037\/xadrez-1.jpg","type":"image\/jpeg"}],"author":"Rodrigo Augusto Batalha Alves","twitter_card":"summary_large_image","twitter_creator":"@EstratConcursos","twitter_site":"@EstratConcursos","twitter_misc":{"Escrito por":"Rodrigo Augusto Batalha Alves","Est. tempo de leitura":"12 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/raio-x-do-icms-o-minimo-que-voce-precisa-saber\/#article","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/raio-x-do-icms-o-minimo-que-voce-precisa-saber\/"},"author":{"name":"Rodrigo Augusto Batalha Alves","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/aa0bf103f86069bff16b1ddfb510b18f"},"headline":"Raio x do ICMS &#8211; O m\u00ednimo que voc\u00ea precisa saber para o xeque-mate","datePublished":"2021-09-22T12:12:00+00:00","dateModified":"2021-09-22T17:09:52+00:00","mainEntityOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/raio-x-do-icms-o-minimo-que-voce-precisa-saber\/"},"wordCount":2764,"commentCount":0,"publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/raio-x-do-icms-o-minimo-que-voce-precisa-saber\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/09\/16110037\/xadrez-1.jpg","articleSection":["Concursos P\u00fablicos"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/raio-x-do-icms-o-minimo-que-voce-precisa-saber\/#respond"]}],"copyrightYear":"2021","copyrightHolder":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/raio-x-do-icms-o-minimo-que-voce-precisa-saber\/","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/raio-x-do-icms-o-minimo-que-voce-precisa-saber\/","name":"Raio x do ICMS - O m\u00ednimo que voc\u00ea precisa saber para o xeque-mate","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/raio-x-do-icms-o-minimo-que-voce-precisa-saber\/#primaryimage"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/raio-x-do-icms-o-minimo-que-voce-precisa-saber\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/09\/16110037\/xadrez-1.jpg","datePublished":"2021-09-22T12:12:00+00:00","dateModified":"2021-09-22T17:09:52+00:00","description":"Fala Galera! Temos aqui o verdadeiro Raio X do ICMS, com aquela jogada de mestre para seu Xeque-mate nos concursos Fiscais!!","breadcrumb":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/raio-x-do-icms-o-minimo-que-voce-precisa-saber\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/raio-x-do-icms-o-minimo-que-voce-precisa-saber\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/raio-x-do-icms-o-minimo-que-voce-precisa-saber\/#primaryimage","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/09\/16110037\/xadrez-1.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/09\/16110037\/xadrez-1.jpg","width":1062,"height":708,"caption":"Raio-X do ICMS"},{"@type":"BreadcrumbList","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/raio-x-do-icms-o-minimo-que-voce-precisa-saber\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.estrategiaconcursos.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Raio x do ICMS &#8211; O m\u00ednimo que voc\u00ea precisa saber para o xeque-mate"}]},{"@type":"WebSite","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","name":"Estrat\u00e9gia Concursos","description":"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.","publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization","name":"Estrat\u00e9gia Concursos","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","width":230,"height":60,"caption":"Estrat\u00e9gia Concursos"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/EstratConcursos"]},{"@type":"Person","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/aa0bf103f86069bff16b1ddfb510b18f","name":"Rodrigo Augusto Batalha Alves","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/54f78a13020d62df814fe30a9ecf7fac2702db4f0b5ec9af6f0bc06ea8f1c178?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/54f78a13020d62df814fe30a9ecf7fac2702db4f0b5ec9af6f0bc06ea8f1c178?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/54f78a13020d62df814fe30a9ecf7fac2702db4f0b5ec9af6f0bc06ea8f1c178?s=96&d=mm&r=g","caption":"Rodrigo Augusto Batalha Alves"},"description":"Cargo Atual: Auditor Fiscal da Receita do Distrito Federal; Aprova\u00e7\u00f5es: SEFAZ DF, Analista de Controle Externo do TCE PE, TRE RJ, TRE SP, Ag\u00eancia Nacional de Minera\u00e7\u00e3o (ANM), Col\u00e9gio Naval; Mestre em Direito pela Universidade Cat\u00f3lica de Bras\u00edlia; P\u00f3s-graduado em Direito Tribut\u00e1rio e Direito Econ\u00f4mico e Financeiro Graduado em Ci\u00eancias Atuariais.","sameAs":["https:\/\/www.instagram.com\/rd.batalha\/"],"url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/robat07gmail-com\/"}]}},"_links":{"self":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/851011","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/users\/2202"}],"replies":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/comments?post=851011"}],"version-history":[{"count":20,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/851011\/revisions"}],"predecessor-version":[{"id":867380,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/851011\/revisions\/867380"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media\/862544"}],"wp:attachment":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media?parent=851011"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/categories?post=851011"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tags?post=851011"},{"taxonomy":"tax_estado","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tax_estado?post=851011"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}