{"id":841248,"date":"2021-08-23T09:00:00","date_gmt":"2021-08-23T12:00:00","guid":{"rendered":"https:\/\/blog-estrategia.mystagingwebsite.com\/blog\/?p=841248"},"modified":"2021-08-27T09:11:06","modified_gmt":"2021-08-27T12:11:06","slug":"carta-aos-assinantes-043","status":"publish","type":"post","link":"https:\/\/www.estrategiaconcursos.com.br\/blog\/carta-aos-assinantes-043\/","title":{"rendered":"Carta aos Assinantes do Estrat\u00e9gia Concursos &#8211; 043"},"content":{"rendered":"\n<p class=\"has-text-align-right has-luminous-vivid-amber-background-color has-background wp-block-paragraph\"><em>Confira, em nossa <strong>quadrag\u00e9sima terceira carta aos assinantes<\/strong>, a nossa programa\u00e7\u00e3o semanal, as novidades do nosso Sistema de Quest\u00f5es e as principais movimenta\u00e7\u00f5es de concursos.<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ol\u00e1, pessoal. Tudo bem?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Prof. Diego Cerqueira<\/strong> por aqui, em nossa <strong><span class=\"has-inline-color has-vivid-purple-color\">quadrag\u00e9sima terceira carta aos Assinantes<\/span><\/strong> do Estrat\u00e9gia Concursos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Estamos na Reta Final para os concursos <strong><span class=\"has-inline-color has-vivid-purple-color\">SEFAZ ES<\/span> <\/strong>e <strong><span class=\"has-inline-color has-vivid-purple-color\">PC AL<\/span>.<\/strong> Ent\u00e3o fiquem ligados na programa\u00e7\u00e3o do <strong><span class=\"has-inline-color has-vivid-purple-color\">Hora da Verdade<\/span><\/strong> nessas semanas finais! Convido os alunos que est\u00e3o se preparado para esses certames a se inscreverem nas <strong><span class=\"has-inline-color has-vivid-purple-color\">\u00c1reas do Candidato<\/span><\/strong> respectivas para ficarem por dentro das transmiss\u00f5es que preparamos para voc\u00eas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Acesse os links abaixo para se inscrever na \u00c1rea do Candidato.<\/em><\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><a href=\"https:\/\/gratis.estrategiaconcursos.com.br\/area-do-candidato-sefaz-es\/\">\u00c1rea do candidato SEFAZ ES<\/a><\/li><li><a href=\"https:\/\/gratis.estrategiaconcursos.com.br\/area-do-candidato-pc-al\/\">\u00c1rea do candidato PC AL<\/a><\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Outro ponto que gostaria de destacar \u00e9 o <strong><span class=\"has-inline-color has-vivid-purple-color\">Projeto 100 Dicas TJ SP<\/span><\/strong>. Todos os dias, at\u00e9 a data da prova, disponibilizaremos <strong>pelo menos 1 dica di\u00e1ria em nosso canal do YouTube<\/strong>, cobrindo todas as disciplinas previstas no edital. Alunos que est\u00e3o se preparando para o TJ SP, n\u00e3o deixem de conferir as dicas especiais da equipe do Estrat\u00e9gia para turbinar a sua prepara\u00e7\u00e3o.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Acesse o link abaixo e confira a playlist com todas as dicas.<\/em><\/p>\n\n\n\n<p class=\"has-text-align-center has-pale-cyan-blue-background-color has-background wp-block-paragraph\"><a href=\"https:\/\/www.youtube.com\/watch?v=4gbx4-Vgo44&amp;list=PL70rxKg7qWNU6Q8nCekDNCMibozWBHWNf\">PROJETO 100 DICAS TJ SP<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Agora, vamos conferir os principais eventos que est\u00e3o programados para a semana?<\/em><\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"block-4e630988-3107-4743-a323-28e776d8b4ad\"><strong>Programa\u00e7\u00e3o Semanal<\/strong> &#8211; Carta aos Assinantes<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\" id=\"block-6d01e560-d5a2-4aae-8daf-5fa1c6a245e0\"><strong><span class=\"has-inline-color has-vivid-purple-color\">1. <strong>SIMULADOS<\/strong><\/span><\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><strong><\/strong><strong>3\u00ba Simulado para 1\u00aa Fase do XXXIII Exame de Ordem \u2013 <\/strong>28 de agosto (<a href=\"https:\/\/gratis.estrategiaconcursos.com.br\/1-fase-xxxiii-exame-de-ordem\/\">Participe<\/a>)<\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\" id=\"block-6d01e560-d5a2-4aae-8daf-5fa1c6a245e0\"><strong><span class=\"has-inline-color has-vivid-purple-color\">2. SEMANAS ESPECIAIS<\/span><\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>Semana Especial dos Concursos Policiais | As oportunidades escondidas da melhor \u00e1rea de 2021 \u2013 <\/strong>23 de agosto (<a href=\"https:\/\/gratis.estrategiaconcursos.com.br\/semana-especial-dos-concursos-policiais-oportunidades-escondidas-melhor-area-2021\/\">Participe<\/a>)<\/li><li><strong>1\u00ba Congresso Nacional dos Concursos de Sa\u00fade | Como conquistar uma das 15 mil vagas \u2013 <\/strong>23 de agosto (<a href=\"https:\/\/gratis.estrategiaconcursos.com.br\/1o-congresso-nacional-dos-concursos-de-saude\/\">Participe<\/a>)<\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\" id=\"block-2461c527-d3b5-41c2-95eb-35e35a7ea148\"><span class=\"has-inline-color has-vivid-purple-color\"><strong>3. <\/strong><\/span><strong><span class=\"has-inline-color has-vivid-purple-color\">ESTRAT\u00c9GIA CONCURSOS &#8211; Webin\u00e1rios<\/span><\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>Concurso TJ SP: 7 dicas para estudar Normas de Corregedoria \u2013 <\/strong>23 de agosto (<a href=\"https:\/\/youtu.be\/ecRYrwRnsNA\">Defina o Lembrete<\/a>)<\/li><li><strong>Monitoria SEJUSP MG (Agente Penitenci\u00e1rio) &#8211; P\u00f3s-Edital \u2013 <\/strong>23 de agosto (<a href=\"https:\/\/youtu.be\/KmHi83kHtng\">Defina o Lembrete<\/a>)<\/li><li><strong>Prepara\u00e7\u00e3o Gratuita &#8211; Come\u00e7ando do Zero: Pol\u00edcia Penal MG &#8211; P\u00f3s-edital \u2013 <\/strong>23 de agosto (<a href=\"https:\/\/gratis.estrategiaconcursos.com.br\/preparacao-gratuita-comecando-do-zero-policia-penal-mg-pos-edital\/\">Defina o Lembrete<\/a>)<\/li><li><strong>SEFAZ CE x SEFAZ AL &#8211; Conhe\u00e7a a Trilha Estrat\u00e9gica de Adapta\u00e7\u00e3o! \u2013 <\/strong>23 de agosto (<a href=\"https:\/\/gratis.estrategiaconcursos.com.br\/sefaz-ce-x-sefaz-al-conheca-a-trilha-estrategica-de-adaptacao\/\">Defina o Lembrete<\/a>)<\/li><li><strong>Concursos de Tribunais de Contas: Plano de estudo b\u00e1sico \u2013 <\/strong>23 de agosto (<a href=\"https:\/\/youtu.be\/XEzoEFvN6Vo\">Defina o Lembrete<\/a>)<\/li><li><strong>Concurso PM PB: Passo Estrat\u00e9gico de Revis\u00e3o (23\/08) \u2013 <\/strong>23 de agosto (<a href=\"https:\/\/youtu.be\/GOz8j16k8Kg\">Defina o Lembrete<\/a>)<\/li><li><strong>TCE AM: Aul\u00e3o Final &#8211; Edifica\u00e7\u00f5es e Obras \u2013 <\/strong>24 de agosto (<a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/cursosPorConcurso\/tribunal-de-contas-do-estado-do-amazonas-tce-am\/\">Defina o Lembrete<\/a>)<\/li><li><strong>Monitoria PF (Agente Administrativo) \u2013 <\/strong>24 de agosto (<a href=\"https:\/\/gratis.estrategiaconcursos.com.br\/area-do-candidato-pf\/\">Defina o Lembrete<\/a>)<\/li><li><strong>5 dicas para ter mais concentra\u00e7\u00e3o e produtividade nos estudos \u2013 <\/strong>24 de agosto (<a href=\"https:\/\/youtu.be\/O5Y4ajH7KxY\">Defina o Lembrete<\/a>)<\/li><li><strong>Concurso TJ RO: Como se preparar para a prova da FGV \u2013 <\/strong>25 de agosto (<a href=\"https:\/\/youtu.be\/U8NbUIFhZrQ\">Defina o Lembrete<\/a>)<\/li><li><strong>Aul\u00e3o Especial para o Banco do Brasil: Inform\u00e1tica &#8211; Prof. Emannuelle Gouveia \u2013 <\/strong>25 de agosto (<a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/cursosPorConcurso\/banco-do-brasil-escriturario-99\/\">Defina o Lembrete<\/a>)<\/li><li><strong>SEFAZ MG &#8211; Seja aprovado com a Trilha Estrat\u00e9gica! \u2013 <\/strong>25 de agosto (<a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/curso\/pacote-completo-p-sefaz-mg-auditor-fiscal-2021-pre-edital\/\">Defina o Lembrete<\/a>)<\/li><li><strong>Mitos e Verdades sobre Concursos P\u00fablicos \u2013 <\/strong>25 de agosto (<a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-2021\/\">Defina o Lembrete<\/a>)<\/li><li><strong>Concurso SEPLAD PA: Passo Estrat\u00e9gico de Revis\u00e3o \u2013 <\/strong>25 de agosto (<a href=\"https:\/\/gratis.estrategiaconcursos.com.br\/e-book-concursos-2021\/\">Defina o Lembrete<\/a>)<\/li><li><strong>Concurso SEFAZ AL: Passo Estrat\u00e9gico de Revis\u00e3o \u2013 <\/strong>26 de agosto (<a href=\"https:\/\/youtu.be\/Nj71b35gfCs\">Defina o Lembrete<\/a>)<\/li><li><strong>Tecnologia da Informa\u00e7\u00e3o: Os 10 assuntos mais cobrados em concursos \u2013 <\/strong>26 de agosto (<a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-ti-2021\/\">Defina o Lembrete<\/a>)<\/li><li><strong>Concurso SEFAZ PR: Saiba por onde come\u00e7ar os estudos \u2013 <\/strong>26 de agosto (<a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-sefaz-pr\/\">Defina o Lembrete<\/a>)<\/li><li><strong>Apostas Finais de Discursivas para PC AL \u2013 Prof. Rodolfo Gracioli \u2013 <\/strong>27 de agosto (<a href=\"https:\/\/youtu.be\/uUWd6_kNNC8\">Defina o Lembrete<\/a>)<\/li><li><strong>Apostas Finais PC AL \u2013 3 em 1 \u2013 <\/strong>27 de agosto (<a href=\"https:\/\/gratis.estrategiaconcursos.com.br\/area-do-candidato-pc-al\/\">Defina o Lembrete<\/a>)<\/li><li><strong>Concursos de Educa\u00e7\u00e3o: Plano de Estudos base para qualquer certame \u2013 <\/strong>27 de agosto (<a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-educacao-2021\/\">Defina o Lembrete<\/a>)<\/li><li><strong>Revis\u00e3o de V\u00e9spera PG DF &#8211; Cargo: Analista Jur\u00eddico &#8211; Direito e Legisla\u00e7\u00e3o \u2013 <\/strong>28 de agosto (<a href=\"https:\/\/gratis.estrategiaconcursos.com.br\/area-do-candidato-pg-df\/\">Defina o Lembrete<\/a>)<\/li><li><strong>Revis\u00e3o de V\u00e9spera PG DF &#8211; Cargo: T\u00e9cnico Jur\u00eddico &#8211; Especialidade: Apoio Administrativo \u2013 <\/strong>28 de agosto (<a href=\"https:\/\/gratis.estrategiaconcursos.com.br\/area-do-candidato-pg-df\/\">Defina o Lembrete<\/a>)<\/li><li><strong>Revis\u00e3o de V\u00e9spera SEFAZ ES \u2013 <\/strong>28 de agosto (<a href=\"https:\/\/gratis.estrategiaconcursos.com.br\/area-do-candidato-sefaz-es\/\">Defina o Lembrete<\/a>)<\/li><li><strong>Revis\u00e3o de V\u00e9spera PC AL \u2013 <\/strong>28 de agosto (<a href=\"https:\/\/gratis.estrategiaconcursos.com.br\/area-do-candidato-pc-al\/\">Defina o Lembrete<\/a>)<\/li><li><strong>Seguran\u00e7a do Trabalho: Quest\u00f5es VUNESP &#8211; Prefeituras de Jaguari\u00fana e Ribeir\u00e3o Preto \u2013 <\/strong>28 de agosto (<a href=\"https:\/\/gratis.estrategiaconcursos.com.br\/ebook-seguranca-trabalho\/\">Defina o Lembrete<\/a>)<\/li><li><strong>O que fazer ap\u00f3s o concurso do TCE AM \u2013 <\/strong>28 de agosto (<a href=\"https:\/\/gratis.estrategiaconcursos.com.br\/area-do-candidato-tce-am\/\">Defina o Lembrete<\/a>)<\/li><li><strong>FUNSA\u00daDE CE &#8211; FGV em Foco \u2013 ODONTOLOGIA \u2013 <\/strong>28 de agosto (<a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/cursosPorConcurso\/fundacao-saude-do-ceara-funsaude-ce\/\">Defina o Lembrete<\/a>)<\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><span class=\"has-inline-color has-vivid-purple-color\">4. <strong>ESTRAT\u00c9GIA CARREIRA JUR\u00cdDICA \u2013 Webin\u00e1rios<\/strong><\/span><\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>Novo crime de viol\u00eancia psicol\u00f3gica contra a mulher \u2013 <\/strong>23 de agosto (<a href=\"https:\/\/youtu.be\/Ri-zkp5fpxA\">Defina o Lembrete<\/a>)<\/li><li><strong>O Caso Cid Moreira &#8211; Entenda as Ferramentas para a Deserda\u00e7\u00e3o \u2013 <\/strong>24 de agosto (<a href=\"https:\/\/gratis.estrategiaconcursos.com.br\/o-caso-cid-moreira-entenda-as-ferramentas-para-a-deserdacao\/\">Defina o Lembrete<\/a>)<\/li><li><strong>Procurador PGE GO &#8211; O melhor roteiro de estudos no p\u00f3s-edital! \u2013 <\/strong>25 de agosto (<a href=\"https:\/\/gratis.estrategiaconcursos.com.br\/procurador-pge-go-o-melhor-roteiro-de-estudos-no-pos-edital\/\">Defina o Lembrete<\/a>)<\/li><li><strong>Como elevar o n\u00edvel de seus estudos para Defensoria P\u00fablica \u2013 <\/strong>25 de agosto (<a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-defensorias-publicas\/\">Defina o Lembrete<\/a>)<\/li><li><strong>A Advocacia Trabalhista Preventiva e Contenciosa \u2013 <\/strong>26 de agosto (<a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/assinaturas-oab\/\">Defina o Lembrete<\/a>)<\/li><\/ul>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"block-544baa21-48b3-40a4-9b25-7e4ba69d9430\"><strong>Sistema de Quest\u00f5es do Estrat\u00e9gia<\/strong> &#8211; Carta aos Assinantes<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">No \u00faltimo final de semana foram<span class=\"has-inline-color has-vivid-purple-color\"> <strong>realizados dois simulados no Sistema de Quest\u00f5es:<\/strong><\/span> <strong>SEFAZ AL e Simulado da Premoni\u00e7\u00e3o PC CE<\/strong>. Gostaria de agradecer a participa\u00e7\u00e3o de todos os alunos e convidar aqueles que ainda n\u00e3o tiveram a oportunidade de realizar os simulados a se inscreverem nos links abaixo. <strong>Os simulados s\u00e3o compostos por quest\u00f5es in\u00e9ditas e ainda est\u00e3o dispon\u00edveis no SQ<\/strong> para que voc\u00ea eleve seus estudos a outro patamar!<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Acesse abaixo os artigos do nosso blog e fa\u00e7a j\u00e1 os simulados.<\/em><\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/simulado-premonicao-sq-pc-ce-inspetor-escrivao\/\">Simulado da Premoni\u00e7\u00e3o para PC CE (Inspetor e Escriv\u00e3o)<strong><em><\/em><\/strong><\/a><\/li><li><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/2-simulado-sq-sefaz-al-auditor-fiscal\/\">2\u00ba Simulado do SQ para SEFAZ AL (Auditor Fiscal)<\/a><\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Temos novidade tamb\u00e9m sobre o t\u00e3o esperado concurso da <strong><span class=\"has-inline-color has-vivid-purple-color\">Pol\u00edcia Penal de MG<\/span>.<\/strong> O edital foi publicado na \u00faltima semana e a equipe do SQ j\u00e1 iniciou a prepara\u00e7\u00e3o de <strong><span class=\"has-inline-color has-vivid-purple-color\">cadernos de quest\u00f5es<\/span><\/strong> para turbinar seu estudo nessa reta final. Os cadernos s\u00e3o compostos de quest\u00f5es do <strong>Instituto Selecon<\/strong>, abordando os principais t\u00f3picos de disciplinas que est\u00e3o previstas no edital do concurso da Pol\u00edcia Penal de MG. O SQ j\u00e1 conta com quase <strong>300 quest\u00f5es<\/strong> distribu\u00eddas em cadernos de Portugu\u00eas, Racioc\u00ednio L\u00f3gico e Inform\u00e1tica, para te auxiliar no estudo e memoriza\u00e7\u00e3o dos principais t\u00f3picos pass\u00edveis de cobran\u00e7a na prova.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Acesse os cadernos dispon\u00edveis no link do nosso blog.<\/em><\/p>\n\n\n\n<p class=\"has-text-align-center has-pale-cyan-blue-background-color has-background wp-block-paragraph\"><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/cadernos-de-questoes-policia-penal-mg\/\">CADERNOS DE QUEST\u00d5ES \u2013 POL\u00cdCIA PENAL DE MG<\/a><\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"block-70e62fc5-ea6c-4280-9c1f-64e4fe8a4c23\"><strong>Agora, vamos ver as principais movimenta\u00e7\u00f5es de concursos da \u00faltima semana?<\/strong><\/h2>\n\n\n\n<ul class=\"wp-block-list\"><li><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-jucepa\/\">JUCEPA<\/a>: Ap\u00f3s muita espera, saiu o edital do concurso Junta Comercial do Estado do Par\u00e1. O documento foi publicado nesta quinta-feira, 19 de agosto, atrav\u00e9s do Di\u00e1rio Oficial do Estado. Sob organiza\u00e7\u00e3o da Funda\u00e7\u00e3o Cetap, s\u00e3o ofertadas 15 vagas imediatas mais cadastro de reserva que est\u00e3o distribu\u00eddas entre cargos de n\u00edvel superior. As inscri\u00e7\u00f5es estar\u00e3o abertas entre os dias 26 de agosto e 20 de outubro. J\u00e1 as provas, est\u00e3o previstas para o dia 12 de dezembro de 2021. Vale frisar que o certame \u00e9 constitu\u00eddo de provas objetivas, discursiva e avalia\u00e7\u00e3o de t\u00edtulos.<\/li><\/ul>\n\n\n\n<ul class=\"wp-block-list\"><li><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-der-pe\/\">DER PE<\/a>: E as novidades n\u00e3o param por a\u00ed! H\u00e1 mais de 10 anos sem realizar um concurso para efetivos, o Departamento de Estradas e Rodagens confirmou, atrav\u00e9s da secret\u00e1ria de infraestrutura do estado, Fernandha Batista, que pretende abrir um novo certame em breve. De acordo com a mesma, a previs\u00e3o \u00e9 que o edital possa ser divulgado ainda no in\u00edcio do primeiro semestre de 2022. A ideia \u00e9 repor o atual quadro de servidores da autarquia que, atualmente, sofre com d\u00e9ficit de pessoal. Estudos est\u00e3o sendo feitos a fim de identificar os cargos e o quantitativo de vagas necess\u00e1rias para o concurso.<\/li><\/ul>\n\n\n\n<ul class=\"wp-block-list\"><li><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-agente-penitenciario-mg\/\">Pol\u00edcia Penal MG<\/a>: O edital do concurso Pol\u00edcia Penal MG foi publicado com 2.420 vagas para o cargo de Agente de Seguran\u00e7a Penitenci\u00e1rio. Do total, 1.944 oportunidades s\u00e3o para o sexo masculino e 476 para o sexo feminino. Entre as principais exig\u00eancias est\u00e1 forma\u00e7\u00e3o de n\u00edvel m\u00e9dio, com sal\u00e1rio inicial no valor de R$ 4.631,25. Os interessados em participar da sele\u00e7\u00e3o devem realizar as inscri\u00e7\u00f5es no per\u00edodo de 22 de outubro a 21 de novembro, no site da banca organizadora, Instituto Selecon, ao custo de R$ 49,16. A aplica\u00e7\u00e3o da prova \u00e9 prevista para 16 de janeiro de 2022.<\/li><\/ul>\n\n\n\n<ul class=\"wp-block-list\"><li><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-policia-civil-rj\/\">PC RJ<\/a>: Ao que tudo indica, chegou ao fim a novela que tratava da banca organizadora do concurso PC RJ para os cargos de Inspetor, Investigador, Perito Criminal, Perito Legista, T\u00e9cnico e Auxiliar de Necropsia. Isso porque, segundo informa\u00e7\u00f5es do Portal de Compras, a Funda\u00e7\u00e3o Get\u00falio Vargas (FGV) foi oficialmente contratada. Para o cargo de Delegado, o edital segue sob responsabilidade do Centro Brasileiro de Pesquisa em Avalia\u00e7\u00e3o e Sele\u00e7\u00e3o e de Promo\u00e7\u00e3o de Eventos (Cebraspe). Vale lembrar que, no total, cinco empresas estavam na disputa. De acordo com o projeto b\u00e1sico, a sele\u00e7\u00e3o prev\u00ea a oferta de 400 vagas imediatas. As oportunidades ser\u00e3o para cargos de n\u00edvel fundamental, m\u00e9dio e superior, com sal\u00e1rios de R$ 4.506,27 a R$ 18.747,95.<\/li><\/ul>\n\n\n\n<ul class=\"wp-block-list\"><li>Concursos Policiais MT [<a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-pc-mt\/\">PC<\/a>, <a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-pm-mt\/\">PM<\/a>, <a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-bombeiro-mt\/\">Bombeiros<\/a>, <a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-politec-mt\/\">Politec<\/a>]: Foram divulgadas as comiss\u00f5es organizadoras para os concursos policiais do Mato Grosso, sendo da Pol\u00edcia Civil, Pol\u00edcia Militar, Bombeiros e Politec. Cargos e vagas ainda ser\u00e3o determinados. A previs\u00e3o \u00e9 que as sele\u00e7\u00f5es ocorram ainda em 2021.<\/li><\/ul>\n\n\n\n<ul class=\"wp-block-list\"><li><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-bombeiro-pa\/\">Bombeiro PA<\/a>: Foi divulgado o Aviso de Abertura de Concorr\u00eancia P\u00fablica que visa a contrata\u00e7\u00e3o da banca organizadora para o pr\u00f3ximo concurso Bombeiro PA. Conforme o documento, a licita\u00e7\u00e3o deve ocorrer em outubro, cujo edital ofertar\u00e1 vagas para Soldado. De acordo com o Termo de Refer\u00eancia [e j\u00e1 adiantado pelo governador], ser\u00e3o ofertadas 405 vagas para o Curso de Forma\u00e7\u00e3o de Pra\u00e7as Bombeiros Militares Combatente (Soldado). O cargo exige forma\u00e7\u00e3o de n\u00edvel m\u00e9dio e oferece sal\u00e1rio de R$ 3.960,00. A expectativa, segundo secret\u00e1ria de Estado de Planejamento e Administra\u00e7\u00e3o (SEPLAD PA), Hana Ghassan, \u00e9 que a sele\u00e7\u00e3o ocorra at\u00e9 o final de 2021.<\/li><\/ul>\n\n\n\n<ul class=\"wp-block-list\"><li><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-prf-3\/\">PRF<\/a>: Foi divulgada no site do Cebraspe, banca organizadora do concurso PRF, a retomada do certame em raz\u00e3o de decis\u00e3o proferida nos autos do Agravo de Instrumento em andamento na 3\u00aa Turma do Tribunal Regional Federal da 5\u00aa Regi\u00e3o (TRF 5). Vale lembrar que a suspens\u00e3o se deu ap\u00f3s uma liminar ser expedida pela 3\u00aa Vara Federal de Sergipe, solicitando uma iniciativa a respeito da reserva de vagas em todas as fases do certame e n\u00e3o somente no resultado final.<\/li><\/ul>\n\n\n\n<ul class=\"wp-block-list\"><li><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-tj-pb-cartorios\/\">Cart\u00f3rio PB<\/a>: Foi formada a comiss\u00e3o organizadora do 2\u00ba Concurso para a Outorga das Delega\u00e7\u00f5es de Servi\u00e7os Notariais e Registrais da Para\u00edba. A decis\u00e3o foi dada por unanimidade pelo Pleno do Tribunal de Justi\u00e7a do Estado. Ainda n\u00e3o se sabe a quantidade de serventias que ser\u00e3o ofertadas. Para concorrer pelo crit\u00e9rio de provimento, o candidato deve ter conclu\u00eddo o curso superior de Direito ou exercido por 10 anos atividade notarial. J\u00e1 para concorrer ao crit\u00e9rio de remo\u00e7\u00e3o, o candidato deve possuir a delega\u00e7\u00e3o por mais de 2 anos.<\/li><\/ul>\n\n\n\n<ul class=\"wp-block-list\"><li><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-dpe-es-defensor\/\">DPE ES<\/a>: O Conselho Superior da Defensoria P\u00fablica do Esp\u00edrito Santo divulgou o regulamento do novo concurso que ofertar\u00e1 vagas para Defensor P\u00fablico Substituto no Estado. Com estudos avan\u00e7ados, o \u00f3rg\u00e3o pretende iniciar os tr\u00e2mites legais o mais r\u00e1pido poss\u00edvel. Para ser empossado o candidato dever\u00e1 ter conclu\u00eddo o curso de bacharelado em Direito, e ter cumprido, \u00e0 data da posse, no m\u00ednimo, 03 anos de atividade jur\u00eddica.<\/li><\/ul>\n\n\n\n<ul class=\"wp-block-list\"><li><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-dpe-am-defensor\/\">DPE AM<\/a>: Uma nova Portaria, publicada no Di\u00e1rio Oficial da Defensoria P\u00fablica do Amazonas, declarou, por dispensa de licita\u00e7\u00e3o, a Funda\u00e7\u00e3o Carlos Chagas (FCC) como a banca organizadora do concurso que ofertar\u00e1 vagas para Defensor Substituto no Estado, com sal\u00e1rio inicial de R$ 14 mil. O regulamento do certame j\u00e1 havia sido publicado em julho. Para concorrer, o candidato deve possuir bacharelado em Direito e 02 anos, no m\u00ednimo, de atividade jur\u00eddica.<\/li><\/ul>\n\n\n\n<ul class=\"wp-block-list\"><li><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-dpe-ms-defensor\/\">DPE MS<\/a>: Foi formada a comiss\u00e3o organizadora do concurso que ofertar\u00e1 vagas para Defensor P\u00fablico Substituto no Estado do Mato Grosso do Sul. O certame est\u00e1 cada vez mais perto de ter o edital publicado, j\u00e1 que o regulamento j\u00e1 havia sido divulgado e a contrata\u00e7\u00e3o da banca FGV, oficializada. Para concorrer ao cargo, o candidato deve possuir diploma de conclus\u00e3o de curso de gradua\u00e7\u00e3o em Direito e comprovar o exerc\u00edcio m\u00ednimo 3 anos de atividade jur\u00eddica.<\/li><\/ul>\n\n\n\n<ul class=\"wp-block-list\"><li><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-tjdft-2021\">TJDFT<\/a>: Durante a realiza\u00e7\u00e3o da 9\u00aa Sess\u00e3o Ordin\u00e1ria por Videoconfer\u00eancia, o Conselho Especial do Tribunal de Justi\u00e7a do Distrito Federal e Territ\u00f3rios aprovou o in\u00edcio da deflagra\u00e7\u00e3o do processo para realiza\u00e7\u00e3o do concurso e o adiantamento dos tr\u00e2mites para publica\u00e7\u00e3o do novo edital de servidores ainda para 2021, considerando a constante necessidade do tribunal. Segundo o Desembargador Romeu Gonzaga Neiva, podem ser ofertadas mais que 409 vagas.<\/li><\/ul>\n\n\n\n<ul class=\"wp-block-list\"><li><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-crefono-3-pr\/\">CREFONO 3<\/a>: O Conselho Regional de Fonoaudiologia 3\u00ba Regi\u00e3o, localizado no Paran\u00e1, divulgou o edital que oferta 5 vagas diretas e 125 vagas para forma\u00e7\u00e3o de cadastro de reserva para cargos de n\u00edvel m\u00e9dio e superior, com sal\u00e1rios de R$ 1.486,92 e R$ 3.377,00. Os interessados devem se inscrever at\u00e9 o dia 20 de setembro de 2021 no endere\u00e7o eletr\u00f4nico do Instituto Quadrix. As taxas de inscri\u00e7\u00e3o foram fixadas em R$ 48,00 (n\u00edvel m\u00e9dio) e R$ 55,00 (n\u00edvel superior). As provas objetivas est\u00e3o previstas para 07 de novembro, no turno da tarde.<\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Desejo a todos uma excelente semana de estudos!<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Abra\u00e7os,<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Prof. Diego Cerqueira<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Confira, em nossa quadrag\u00e9sima terceira carta aos assinantes, a nossa programa\u00e7\u00e3o semanal, as novidades do nosso Sistema de Quest\u00f5es e as principais movimenta\u00e7\u00f5es de concursos. Ol\u00e1, pessoal. Tudo bem? Prof. Diego Cerqueira por aqui, em nossa quadrag\u00e9sima terceira carta aos Assinantes do Estrat\u00e9gia Concursos. Estamos na Reta Final para os concursos SEFAZ ES e PC [&hellip;]<\/p>\n","protected":false},"author":1789,"featured_media":841265,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"post_tipo":"article","footnotes":""},"categories":[1],"tags":[],"tax_estado":[219964,219965,219966,219967,219968,219969,219963,219970,219971,219972,219973,219974,219975,219976,219977,219978,219979,219980,219981,219982,219983,219984,219985,219986,219987,219988,219989,219990],"class_list":["post-841248","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cursos-e-concursos","tax_estado-ac","tax_estado-al","tax_estado-am","tax_estado-ap","tax_estado-ba","tax_estado-ce","tax_estado-concursos-federais","tax_estado-df","tax_estado-es","tax_estado-go","tax_estado-ma","tax_estado-mg","tax_estado-ms","tax_estado-mt","tax_estado-pa","tax_estado-pb","tax_estado-pe","tax_estado-pi","tax_estado-pr","tax_estado-rj","tax_estado-rn","tax_estado-ro","tax_estado-rr","tax_estado-rs","tax_estado-sc","tax_estado-se","tax_estado-sp","tax_estado-to"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Carta aos Assinantes do Estrat\u00e9gia Concursos - 043<\/title>\n<meta name=\"description\" content=\"Confira, em nossa 43\u00aa carta aos assinantes, a nossa programa\u00e7\u00e3o semanal, as novidades do nosso SQ e as principais movimenta\u00e7\u00f5es de concursos.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/carta-aos-assinantes-043\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Carta aos Assinantes do Estrat\u00e9gia Concursos - 043\" \/>\n<meta property=\"og:description\" content=\"Confira, em nossa 43\u00aa carta aos assinantes, a nossa programa\u00e7\u00e3o semanal, as novidades do nosso SQ e as principais movimenta\u00e7\u00f5es de concursos.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/carta-aos-assinantes-043\/\" \/>\n<meta property=\"og:site_name\" content=\"Estrat\u00e9gia Concursos\" \/>\n<meta property=\"article:published_time\" content=\"2021-08-23T12:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-08-27T12:11:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/08\/20111656\/imagem-carta-aos-assinantes-2.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"450\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Coordena\u00e7\u00e3o Estrat\u00e9gia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:site\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Coordena\u00e7\u00e3o Estrat\u00e9gia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"10 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/carta-aos-assinantes-043\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/carta-aos-assinantes-043\\\/\"},\"author\":{\"name\":\"Coordena\u00e7\u00e3o Estrat\u00e9gia\",\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/#\\\/schema\\\/person\\\/ba5fab3b1fa4a358429e37bc50f74021\"},\"headline\":\"Carta aos Assinantes do Estrat\u00e9gia Concursos &#8211; 043\",\"datePublished\":\"2021-08-23T12:00:00+00:00\",\"dateModified\":\"2021-08-27T12:11:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/carta-aos-assinantes-043\\\/\"},\"wordCount\":2264,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/carta-aos-assinantes-043\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dhg1h5j42swfq.cloudfront.net\\\/2021\\\/08\\\/20111656\\\/imagem-carta-aos-assinantes-2.png\",\"articleSection\":[\"Concursos P\u00fablicos\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/carta-aos-assinantes-043\\\/#respond\"]}],\"copyrightYear\":\"2021\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/carta-aos-assinantes-043\\\/\",\"url\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/carta-aos-assinantes-043\\\/\",\"name\":\"Carta aos Assinantes do Estrat\u00e9gia Concursos - 043\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/carta-aos-assinantes-043\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/carta-aos-assinantes-043\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dhg1h5j42swfq.cloudfront.net\\\/2021\\\/08\\\/20111656\\\/imagem-carta-aos-assinantes-2.png\",\"datePublished\":\"2021-08-23T12:00:00+00:00\",\"dateModified\":\"2021-08-27T12:11:06+00:00\",\"description\":\"Confira, em nossa 43\u00aa carta aos assinantes, a nossa programa\u00e7\u00e3o semanal, as novidades do nosso SQ e as principais movimenta\u00e7\u00f5es de concursos.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/carta-aos-assinantes-043\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/carta-aos-assinantes-043\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/carta-aos-assinantes-043\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dhg1h5j42swfq.cloudfront.net\\\/2021\\\/08\\\/20111656\\\/imagem-carta-aos-assinantes-2.png\",\"contentUrl\":\"https:\\\/\\\/dhg1h5j42swfq.cloudfront.net\\\/2021\\\/08\\\/20111656\\\/imagem-carta-aos-assinantes-2.png\",\"width\":800,\"height\":450,\"caption\":\"carta aos assinantes\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/carta-aos-assinantes-043\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Carta aos Assinantes do Estrat\u00e9gia Concursos &#8211; 043\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/\",\"name\":\"Estrat\u00e9gia Concursos\",\"description\":\"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/#organization\",\"name\":\"Estrat\u00e9gia Concursos\",\"url\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dhg1h5j42swfq.cloudfront.net\\\/2025\\\/06\\\/03203428\\\/logo_concursos-1.jpg\",\"contentUrl\":\"https:\\\/\\\/dhg1h5j42swfq.cloudfront.net\\\/2025\\\/06\\\/03203428\\\/logo_concursos-1.jpg\",\"width\":230,\"height\":60,\"caption\":\"Estrat\u00e9gia Concursos\"},\"image\":{\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/EstratConcursos\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/#\\\/schema\\\/person\\\/ba5fab3b1fa4a358429e37bc50f74021\",\"name\":\"Coordena\u00e7\u00e3o Estrat\u00e9gia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/adff33ff18541ba37c900dd2b1e82dbfb0fe33d873b92636b4827a8da462feb3?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/adff33ff18541ba37c900dd2b1e82dbfb0fe33d873b92636b4827a8da462feb3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/adff33ff18541ba37c900dd2b1e82dbfb0fe33d873b92636b4827a8da462feb3?s=96&d=mm&r=g\",\"caption\":\"Coordena\u00e7\u00e3o Estrat\u00e9gia\"},\"url\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/author\\\/victor-tanakaaestrategiaconcursos-com-br\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Carta aos Assinantes do Estrat\u00e9gia Concursos - 043","description":"Confira, em nossa 43\u00aa carta aos assinantes, a nossa programa\u00e7\u00e3o semanal, as novidades do nosso SQ e as principais movimenta\u00e7\u00f5es de concursos.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.estrategiaconcursos.com.br\/blog\/carta-aos-assinantes-043\/","og_locale":"pt_BR","og_type":"article","og_title":"Carta aos Assinantes do Estrat\u00e9gia Concursos - 043","og_description":"Confira, em nossa 43\u00aa carta aos assinantes, a nossa programa\u00e7\u00e3o semanal, as novidades do nosso SQ e as principais movimenta\u00e7\u00f5es de concursos.","og_url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/carta-aos-assinantes-043\/","og_site_name":"Estrat\u00e9gia Concursos","article_published_time":"2021-08-23T12:00:00+00:00","article_modified_time":"2021-08-27T12:11:06+00:00","og_image":[{"width":800,"height":450,"url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/08\/20111656\/imagem-carta-aos-assinantes-2.png","type":"image\/png"}],"author":"Coordena\u00e7\u00e3o Estrat\u00e9gia","twitter_card":"summary_large_image","twitter_creator":"@EstratConcursos","twitter_site":"@EstratConcursos","twitter_misc":{"Escrito por":"Coordena\u00e7\u00e3o Estrat\u00e9gia","Est. tempo de leitura":"10 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/carta-aos-assinantes-043\/#article","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/carta-aos-assinantes-043\/"},"author":{"name":"Coordena\u00e7\u00e3o Estrat\u00e9gia","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/ba5fab3b1fa4a358429e37bc50f74021"},"headline":"Carta aos Assinantes do Estrat\u00e9gia Concursos &#8211; 043","datePublished":"2021-08-23T12:00:00+00:00","dateModified":"2021-08-27T12:11:06+00:00","mainEntityOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/carta-aos-assinantes-043\/"},"wordCount":2264,"commentCount":0,"publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/carta-aos-assinantes-043\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/08\/20111656\/imagem-carta-aos-assinantes-2.png","articleSection":["Concursos P\u00fablicos"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/carta-aos-assinantes-043\/#respond"]}],"copyrightYear":"2021","copyrightHolder":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/carta-aos-assinantes-043\/","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/carta-aos-assinantes-043\/","name":"Carta aos Assinantes do Estrat\u00e9gia Concursos - 043","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/carta-aos-assinantes-043\/#primaryimage"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/carta-aos-assinantes-043\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/08\/20111656\/imagem-carta-aos-assinantes-2.png","datePublished":"2021-08-23T12:00:00+00:00","dateModified":"2021-08-27T12:11:06+00:00","description":"Confira, em nossa 43\u00aa carta aos assinantes, a nossa programa\u00e7\u00e3o semanal, as novidades do nosso SQ e as principais movimenta\u00e7\u00f5es de concursos.","breadcrumb":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/carta-aos-assinantes-043\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/carta-aos-assinantes-043\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/carta-aos-assinantes-043\/#primaryimage","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/08\/20111656\/imagem-carta-aos-assinantes-2.png","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/08\/20111656\/imagem-carta-aos-assinantes-2.png","width":800,"height":450,"caption":"carta aos assinantes"},{"@type":"BreadcrumbList","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/carta-aos-assinantes-043\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.estrategiaconcursos.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Carta aos Assinantes do Estrat\u00e9gia Concursos &#8211; 043"}]},{"@type":"WebSite","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","name":"Estrat\u00e9gia Concursos","description":"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.","publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization","name":"Estrat\u00e9gia Concursos","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","width":230,"height":60,"caption":"Estrat\u00e9gia Concursos"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/EstratConcursos"]},{"@type":"Person","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/ba5fab3b1fa4a358429e37bc50f74021","name":"Coordena\u00e7\u00e3o Estrat\u00e9gia","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/adff33ff18541ba37c900dd2b1e82dbfb0fe33d873b92636b4827a8da462feb3?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/adff33ff18541ba37c900dd2b1e82dbfb0fe33d873b92636b4827a8da462feb3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/adff33ff18541ba37c900dd2b1e82dbfb0fe33d873b92636b4827a8da462feb3?s=96&d=mm&r=g","caption":"Coordena\u00e7\u00e3o Estrat\u00e9gia"},"url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/victor-tanakaaestrategiaconcursos-com-br\/"}]}},"_links":{"self":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/841248","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/users\/1789"}],"replies":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/comments?post=841248"}],"version-history":[{"count":0,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/841248\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media\/841265"}],"wp:attachment":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media?parent=841248"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/categories?post=841248"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tags?post=841248"},{"taxonomy":"tax_estado","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tax_estado?post=841248"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}