{"id":836144,"date":"2021-08-13T21:28:45","date_gmt":"2021-08-14T00:28:45","guid":{"rendered":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?p=836144"},"modified":"2021-08-14T11:09:44","modified_gmt":"2021-08-14T14:09:44","slug":"concurso-pm-al-medidas-seguranca-covid","status":"publish","type":"post","link":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-pm-al-medidas-seguranca-covid\/","title":{"rendered":"Concurso PM AL: quais as medidas de seguran\u00e7a para Covid?"},"content":{"rendered":"\n<p>Afinal, candidatos do <strong>concurso PM AL<\/strong>, voc\u00eas j\u00e1 est\u00e3o por dentro das medidas de seguran\u00e7a contra a Covid-19 para o dia da prova?<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.direcaoconcursos.com.br\/uploads\/2019\/04\/pmal03.jpg\" alt=\"\" width=\"712\" height=\"475\"\/><figcaption>Provas do concurso PM AL ocorrem em 15\/08; veja as medidas contra a Covid<\/figcaption><\/figure><\/div>\n\n\n\n<p>Como voc\u00eas sabem, foram registradas 67.884 inscri\u00e7\u00f5es, sendo 61.455 para o cargo de Soldado Combatente e 6.429 para Oficial Combatente. Ou seja, \u00e9 hora de levar o assunto a s\u00e9rio!<\/p>\n\n\n\n<p>De acordo com um comunicado do <a href=\"https:\/\/www.cebraspe.org.br\/concursos\/PM_AL_21\" target=\"_blank\" rel=\"noreferrer noopener\">Cebraspe<\/a>, respons\u00e1vel pela organiza\u00e7\u00e3o do concurso PM AL, as medidas de seguran\u00e7as contra a Covid-19 ser\u00e3o:<\/p>\n\n\n\n<ul class=\"has-very-light-gray-to-cyan-bluish-gray-gradient-background has-background wp-block-list\"><li>a) comparecer ao local de aplica\u00e7\u00e3o usando m\u00e1scara e portando m\u00e1scaras reservas, se necess\u00e1rio, de modo a possibilitar a troca de sua m\u00e1scara a cada duas horas;<\/li><li>b) armazenar as m\u00e1scaras usadas em saco pl\u00e1stico transparente, que dever\u00e1 ser trazido pelo candidato;<\/li><li>c) permanecer de m\u00e1scara durante todo o tempo em que estiver nas depend\u00eancias dos locais de aplica\u00e7\u00e3o de provas;<\/li><li>d) submeter-se \u00e0 verifica\u00e7\u00e3o da temperatura corporal para acesso ao local de aplica\u00e7\u00e3o, observado o subitem 7.1.5 deste edital;<\/li><li>e) observar o distanciamento adequado, conforme demarca\u00e7\u00e3o do piso com fita adesiva em frente ao port\u00e3o de acesso ao local de aplica\u00e7\u00e3o, na entrada das salas de provas e dos banheiros;<\/li><li>f) observar o distanciamento m\u00ednimo exigido na legisla\u00e7\u00e3o aplic\u00e1vel entre os candidatos e entre membros da equipe de aplica\u00e7\u00e3o nas salas de aplica\u00e7\u00e3o das provas;<\/li><li>g) verificar o seu hor\u00e1rio de acesso ao local de provas, conforme informado na consulta individual, em link espec\u00edfico, em que ser\u00e3o disponibilizadas as informa\u00e7\u00f5es relativas a seu grupo e a seu hor\u00e1rio de entrada;<\/li><li>h) submeter-se a pr\u00e9-identifica\u00e7\u00e3o realizada pela equipe de campo na chegada dos candidatos ao local de aplica\u00e7\u00e3o, sem contato f\u00edsico e sem o manuseio de documentos ou de qualquer outro objeto dos candidatos, podendo ser solicitado que o candidato abaixe a sua m\u00e1scara, de modo a permitir a visualiza\u00e7\u00e3o do seu rosto \u2014 concedendo-se somente ao candidato a manipula\u00e7\u00e3o de sua m\u00e1scara \u2014, mantendo-se o distanciamento m\u00ednimo exigido na legisla\u00e7\u00e3o aplic\u00e1vel de qualquer outro candidato ou membro da equipe de aplica\u00e7\u00e3o;<\/li><li>i) permanecer de m\u00e1scara ao se retirar de sala para uso dos banheiros e observar os procedimentos de higieniza\u00e7\u00e3o das m\u00e3os nesses ambientes;<\/li><li>j) manter os cabelos arrumados de forma que n\u00e3o caiam sobre sua face enquanto estiver dentro dos locais de aplica\u00e7\u00e3o;<\/li><li>k) submeter-se ao controle de sa\u00edda dos candidatos ao t\u00e9rmino das provas para evitar aglomera\u00e7\u00e3o.<\/li><\/ul>\n\n\n\n<p><strong>7.1.1<\/strong> Somente ser\u00e1 permitido o ingresso de candidato ao local de aplica\u00e7\u00e3o usando m\u00e1scara.<\/p>\n\n\n\n<p><strong>7.1.1.1<\/strong> As m\u00e1scaras poder\u00e3o ser descart\u00e1veis, de tecido ou de qualquer outro material. As m\u00e1scaras, inclusive, as descart\u00e1veis e as cir\u00fargicas, n\u00e3o poder\u00e3o ser modificadas\/adulteradas, bem como as de tecido n\u00e3o poder\u00e3o ser de material transparente ou conter qualquer tipo de perfura\u00e7\u00e3o. <\/p>\n\n\n\n<p>Caso o Cebraspe identifique altera\u00e7\u00e3o, recorte, retirada de camadas de prote\u00e7\u00e3o, adapta\u00e7\u00e3o ou inadequa\u00e7\u00e3o no uso de m\u00e1scaras, ser\u00e1 solicitado ao candidato que fa\u00e7a o descarte e a substitui\u00e7\u00e3o da m\u00e1scara inadequada e coloque outra que cumpra os crit\u00e9rios de biosseguran\u00e7a para garantir sua perman\u00eancia no local de provas. <\/p>\n\n\n\n<p>O Cebraspe n\u00e3o fornecer\u00e1 m\u00e1scaras. Aconselha-se que o candidato tenha m\u00e1scaras reservas.<\/p>\n\n\n\n<p><strong>7.1.2<\/strong> Caso deseje, o candidato poder\u00e1 comparecer ao local de aplica\u00e7\u00e3o usando, al\u00e9m da m\u00e1scara, protetor facial transparente (estilo viseira), vestimentas descart\u00e1veis (macac\u00e3o imperme\u00e1vel), luvas descart\u00e1veis (desde que tenham colora\u00e7\u00e3o leitosa ou semitransparente), \u00f3culos de prote\u00e7\u00e3o transparente e toalhas de papel para higieniza\u00e7\u00e3o de m\u00e3os e objetos, independentemente da higieniza\u00e7\u00e3o a ser feita pela equipe do Cebraspe. <\/p>\n\n\n\n<p>O candidato tamb\u00e9m dever\u00e1 levar o seu pr\u00f3prio recipiente contendo \u00e1lcool em gel, desde que esse recipiente seja transparente.<\/p>\n\n\n\n<p><strong>7.1.3<\/strong> As m\u00e1scaras e os frascos de \u00e1lcool em gel 70% dever\u00e3o ser de uso individual e n\u00e3o poder\u00e3o ser compartilhados entre os candidatos.<\/p>\n\n\n\n<p><strong>7.1.4<\/strong> O Cebraspe n\u00e3o fornecer\u00e1 m\u00e1scaras nem frascos de \u00e1lcool em gel 70% aos candidatos, exceto na forma do subitem 7.2 deste edital.<\/p>\n\n\n\n<p><strong>7.1.5<\/strong> Caso a temperatura corporal do candidato, aferida no momento de sua chegada ao local de aplica\u00e7\u00e3o, for igual ou inferior a 37,5 \u00b0C, ser\u00e1 permitido o seu ingresso ao local de aplica\u00e7\u00e3o. Se a temperatura corporal do candidato, aferida no momento de sua chegada ao local de aplica\u00e7\u00e3o, for superior a 37,5 \u00b0C, ser\u00e1 imediatamente realizada uma segunda aferi\u00e7\u00e3o; se a segunda aferi\u00e7\u00e3o confirmar que o candidato se encontra com temperatura corporal superior a 37,5 \u00b0C, o candidato poder\u00e1 ser encaminhado para realizar as provas em sala especial.<\/p>\n\n\n\n<p><strong>7.2<\/strong> O Cebraspe disponibilizar\u00e1 frascos de \u00e1lcool em gel 70% nas salas e nos locais de circula\u00e7\u00e3o, bem como sab\u00e3o l\u00edquido e papel toalha nos banheiros.<\/p>\n\n\n\n<p><strong>7.3<\/strong> Recomenda-se que cada candidato leve \u00e1gua para o seu pr\u00f3prio consumo, em embalagem transparente, para evitar a utiliza\u00e7\u00e3o de bebedouros ou qualquer outro dispositivo de fornecimento coletivo de \u00e1gua para beber.<\/p>\n\n\n\n<p><strong>7.4<\/strong> O candidato que informar, na data de aplica\u00e7\u00e3o das provas, que est\u00e1 acometido pela Covid-19 n\u00e3o poder\u00e1 realiz\u00e1-las.<\/p>\n\n\n\n<p><strong>7.5<\/strong> Outras informa\u00e7\u00f5es a respeito das a\u00e7\u00f5es adotadas e dos procedimentos gerais de preven\u00e7\u00e3o do coronav\u00edrus nos locais de provas estar\u00e3o dispon\u00edveis no endere\u00e7o eletr\u00f4nico www.cebraspe.org.br.<\/p>\n\n\n\n<p>Ent\u00e3o j\u00e1 sabe, caros estrategistas, siga corretamente as orienta\u00e7\u00f5es acima e tenha tranquilidade para realizar a avalia\u00e7\u00e3o deste grande certame, afinal, s\u00e3o <strong>1.060 vagas<\/strong>, distribu\u00eddas entre os cargos de Soldado e Oficial, com sal\u00e1rios que v\u00e3o de R$ 4.250,06 a R$ 8.099,94. <\/p>\n\n\n\n<p class=\"has-text-align-center\"><strong>Para mais informa\u00e7\u00f5es sobre as medidas de preven\u00e7\u00e3o contra a Covid-19 para o concurso PM AL, acesse o link abaixo. Preparamos um artigo completo para voc\u00ea!<\/strong><\/p>\n\n\n\n<p class=\"has-text-align-center has-background\" style=\"background-color:#d7e2e7;font-size:clamp(14.082px, 0.88rem + ((1vw - 3.2px) * 0.678), 21px);px\"><strong><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-pm-al\/\" target=\"_blank\" rel=\"noreferrer noopener\">Concurso PM AL<\/a><\/strong><\/p>\n\n\n\n<h2 class=\"has-text-align-center wp-block-heading\" id=\"cursos-assinatura\"><strong><em>Quer estudar para concurso PM AL?<\/em><\/strong><\/h2>\n\n\n\n<div class=\"container\" id=\"boxes\">\n  <div class=\"row\">\n\n    <div class=\"col-sm\">\n      <div class=\"banner-policial\" id=\"box-assinatura\">\n        <h3 class=\"titulo-assinatura\">Concurso PM AL<\/h3>\n        <p class=\"subtitulo-assinatura\">Conhe\u00e7a os cursos<\/p>\n        <div class=\"box-botao\">\n          <a class=\"btn-assinatura\" target=\"_blank\" href=\"https:\/\/www.estrategiaconcursos.com.br\/cursosPorConcurso\/pm-al\/\" role=\"button\" rel=\"noopener noreferrer\">Conhe\u00e7a mais<\/a>\n        <\/div>\n      <\/div>\n  \n    <\/div>\n\n  <\/div>\n<\/div>\n\n\n\n<div class=\"container\" id=\"boxes\">\n  <div class=\"row\">\n\n    <div class=\"col-sm\">\n      <div class=\"estrategia\" id=\"box-assinatura\">\n        <h3 class=\"titulo-assinatura\">Assinatura Concursos<\/h3>\n        <p class=\"subtitulo-assinatura\">Assinatura de 1 ano ou 2 anos<\/p>\n        <div class=\"box-botao\">\n          <a class=\"btn-assinatura\" target=\"_blank\" href=\"https:\/\/www.estrategiaconcursos.com.br\/assinaturas\/\" role=\"button\" rel=\"noopener noreferrer\">ASSINE AGORA<\/a>\n        <\/div>\n      <\/div>\n     \n    <\/div><\/div><\/div>\n\n\n\n<div class=\"container\" id=\"boxes\">\n  <div class=\"row\">\n\n    <div class=\"col-sm\" id=\"boxes-concursos\">\n      <div style=\"background-color: #005DAD;\" class=\"conteudo-concursos\" id=\"box-concursos\">\n        <h3 class=\"titulo-assinatura\">Concursos Abertos<\/h3>\n        <p class=\"subtitulo-assinatura\">Os editais publicados<\/p>\n        <div class=\"box-botao\">\n          <a class=\"btn-assinatura\" target=\"_blank\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-abertos\/\" role=\"button\" rel=\"noopener noreferrer\">Conhe\u00e7a Agora<\/a>\n        <\/div>\n      <\/div>\n    <\/div>\n\n    <div class=\"col-sm\" id=\"boxes-concursos\">\n      <div style=\"background-color: #1A7ED5;\" class=\"conteudo-concursos\" id=\"box-concursos\">\n        <h3 class=\"titulo-assinatura\">Concursos 2021<\/h3>\n        <p class=\"subtitulo-assinatura\">As oportunidades previstas<\/p>\n        <div class=\"box-botao\">\n          <a class=\"btn-assinatura\" target=\"_blank\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-2021\/\" role=\"button\" rel=\"noopener noreferrer\">Conhe\u00e7a Agora<\/a>\n        <\/div>\n      <\/div>\n    <\/div>\n\n    <div class=\"col-sm\" id=\"boxes-concursos\">\n      <div style=\"background-color: #419FF0;\" class=\"conteudo-concursos\" id=\"box-concursos\">\n        <h3 class=\"titulo-assinatura\">Concursos 2022<\/h3>\n        <p class=\"subtitulo-assinatura\">Vagas para o pr\u00f3ximo ano<\/p>\n        <div class=\"box-botao\">\n          <a class=\"btn-assinatura\" target=\"_blank\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-2022\/\" role=\"button\" rel=\"noopener noreferrer\">Conhe\u00e7a Agora<\/a>\n        <\/div>\n      <\/div>\n    <\/div>\n\n  <\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Afinal, candidatos do concurso PM AL, voc\u00eas j\u00e1 est\u00e3o por dentro das medidas de seguran\u00e7a contra a Covid-19 para o dia da prova? Como voc\u00eas sabem, foram registradas 67.884 inscri\u00e7\u00f5es, sendo 61.455 para o cargo de Soldado Combatente e 6.429 para Oficial Combatente. Ou seja, \u00e9 hora de levar o assunto a s\u00e9rio! De acordo [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":740957,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"post_tipo":"news","footnotes":""},"categories":[220186,220187,220219],"tags":[],"tax_estado":[219965],"class_list":["post-836144","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-policial-oficial","category-policial-pracas","category-noticias","tax_estado-al"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.2 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Concurso PM AL: quais as medidas de seguran\u00e7a para Covid?<\/title>\n<meta name=\"description\" content=\"Afinal, candidatos do concurso PM AL, voc\u00eas j\u00e1 est\u00e3o por dentro das medidas de seguran\u00e7a contra a Covid-19 para o dia da prova? Confira!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-pm-al-medidas-seguranca-covid\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Concurso PM AL: quais as medidas de seguran\u00e7a para Covid?\" \/>\n<meta property=\"og:description\" content=\"Afinal, candidatos do concurso PM AL, voc\u00eas j\u00e1 est\u00e3o por dentro das medidas de seguran\u00e7a contra a Covid-19 para o dia da prova? Confira!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-pm-al-medidas-seguranca-covid\/\" \/>\n<meta property=\"og:site_name\" content=\"Estrat\u00e9gia Concursos\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/EstrategiaConcursos\" \/>\n<meta property=\"article:published_time\" content=\"2021-08-14T00:28:45+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-08-14T14:09:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/05\/14121551\/pm-al.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"768\" \/>\n\t<meta property=\"og:image:height\" content=\"432\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Coordena\u00e7\u00e3o\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:site\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Coordena\u00e7\u00e3o\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-pm-al-medidas-seguranca-covid\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-pm-al-medidas-seguranca-covid\/\"},\"author\":{\"name\":\"Coordena\u00e7\u00e3o\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/b4a388c97673c5f483d72185668afa1f\"},\"headline\":\"Concurso PM AL: quais as medidas de seguran\u00e7a para Covid?\",\"datePublished\":\"2021-08-14T00:28:45+00:00\",\"dateModified\":\"2021-08-14T14:09:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-pm-al-medidas-seguranca-covid\/\"},\"wordCount\":1070,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-pm-al-medidas-seguranca-covid\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/05\/14121551\/pm-al.jpg\",\"articleSection\":[\"Policial (PM\/BM - Oficial)\",\"Policial (PM\/BM - Pra\u00e7as)\",\"\u00daltimas not\u00edcias\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-pm-al-medidas-seguranca-covid\/#respond\"]}],\"copyrightYear\":\"2021\",\"copyrightHolder\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-pm-al-medidas-seguranca-covid\/\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-pm-al-medidas-seguranca-covid\/\",\"name\":\"Concurso PM AL: quais as medidas de seguran\u00e7a para Covid?\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-pm-al-medidas-seguranca-covid\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-pm-al-medidas-seguranca-covid\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/05\/14121551\/pm-al.jpg\",\"datePublished\":\"2021-08-14T00:28:45+00:00\",\"dateModified\":\"2021-08-14T14:09:44+00:00\",\"description\":\"Afinal, candidatos do concurso PM AL, voc\u00eas j\u00e1 est\u00e3o por dentro das medidas de seguran\u00e7a contra a Covid-19 para o dia da prova? Confira!\",\"breadcrumb\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-pm-al-medidas-seguranca-covid\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-pm-al-medidas-seguranca-covid\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-pm-al-medidas-seguranca-covid\/#primaryimage\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/05\/14121551\/pm-al.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/05\/14121551\/pm-al.jpg\",\"width\":768,\"height\":432,\"caption\":\"PM AL\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-pm-al-medidas-seguranca-covid\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Concurso PM AL: quais as medidas de seguran\u00e7a para Covid?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"name\":\"Estrat\u00e9gia Concursos\",\"description\":\"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.\",\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\",\"name\":\"Estrat\u00e9gia Concursos\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"width\":230,\"height\":60,\"caption\":\"Estrat\u00e9gia Concursos\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/EstratConcursos\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/b4a388c97673c5f483d72185668afa1f\",\"name\":\"Coordena\u00e7\u00e3o\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/b720319e4c9a967eb58678d110f4fe35452fc5d5f97b202bac7b8acceb18c6ad?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/b720319e4c9a967eb58678d110f4fe35452fc5d5f97b202bac7b8acceb18c6ad?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/b720319e4c9a967eb58678d110f4fe35452fc5d5f97b202bac7b8acceb18c6ad?s=96&d=mm&r=g\",\"caption\":\"Coordena\u00e7\u00e3o\"},\"sameAs\":[\"https:\/\/www.facebook.com\/EstrategiaConcursos\",\"https:\/\/x.com\/EstratConcursos\"],\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/estrategia2013\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Concurso PM AL: quais as medidas de seguran\u00e7a para Covid?","description":"Afinal, candidatos do concurso PM AL, voc\u00eas j\u00e1 est\u00e3o por dentro das medidas de seguran\u00e7a contra a Covid-19 para o dia da prova? Confira!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-pm-al-medidas-seguranca-covid\/","og_locale":"pt_BR","og_type":"article","og_title":"Concurso PM AL: quais as medidas de seguran\u00e7a para Covid?","og_description":"Afinal, candidatos do concurso PM AL, voc\u00eas j\u00e1 est\u00e3o por dentro das medidas de seguran\u00e7a contra a Covid-19 para o dia da prova? Confira!","og_url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-pm-al-medidas-seguranca-covid\/","og_site_name":"Estrat\u00e9gia Concursos","article_author":"https:\/\/www.facebook.com\/EstrategiaConcursos","article_published_time":"2021-08-14T00:28:45+00:00","article_modified_time":"2021-08-14T14:09:44+00:00","og_image":[{"width":768,"height":432,"url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/05\/14121551\/pm-al.jpg","type":"image\/jpeg"}],"author":"Coordena\u00e7\u00e3o","twitter_card":"summary_large_image","twitter_creator":"@EstratConcursos","twitter_site":"@EstratConcursos","twitter_misc":{"Escrito por":"Coordena\u00e7\u00e3o","Est. tempo de leitura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-pm-al-medidas-seguranca-covid\/#article","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-pm-al-medidas-seguranca-covid\/"},"author":{"name":"Coordena\u00e7\u00e3o","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/b4a388c97673c5f483d72185668afa1f"},"headline":"Concurso PM AL: quais as medidas de seguran\u00e7a para Covid?","datePublished":"2021-08-14T00:28:45+00:00","dateModified":"2021-08-14T14:09:44+00:00","mainEntityOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-pm-al-medidas-seguranca-covid\/"},"wordCount":1070,"commentCount":0,"publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-pm-al-medidas-seguranca-covid\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/05\/14121551\/pm-al.jpg","articleSection":["Policial (PM\/BM - Oficial)","Policial (PM\/BM - Pra\u00e7as)","\u00daltimas not\u00edcias"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-pm-al-medidas-seguranca-covid\/#respond"]}],"copyrightYear":"2021","copyrightHolder":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-pm-al-medidas-seguranca-covid\/","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-pm-al-medidas-seguranca-covid\/","name":"Concurso PM AL: quais as medidas de seguran\u00e7a para Covid?","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-pm-al-medidas-seguranca-covid\/#primaryimage"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-pm-al-medidas-seguranca-covid\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/05\/14121551\/pm-al.jpg","datePublished":"2021-08-14T00:28:45+00:00","dateModified":"2021-08-14T14:09:44+00:00","description":"Afinal, candidatos do concurso PM AL, voc\u00eas j\u00e1 est\u00e3o por dentro das medidas de seguran\u00e7a contra a Covid-19 para o dia da prova? Confira!","breadcrumb":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-pm-al-medidas-seguranca-covid\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-pm-al-medidas-seguranca-covid\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-pm-al-medidas-seguranca-covid\/#primaryimage","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/05\/14121551\/pm-al.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/05\/14121551\/pm-al.jpg","width":768,"height":432,"caption":"PM AL"},{"@type":"BreadcrumbList","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-pm-al-medidas-seguranca-covid\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.estrategiaconcursos.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Concurso PM AL: quais as medidas de seguran\u00e7a para Covid?"}]},{"@type":"WebSite","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","name":"Estrat\u00e9gia Concursos","description":"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.","publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization","name":"Estrat\u00e9gia Concursos","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","width":230,"height":60,"caption":"Estrat\u00e9gia Concursos"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/EstratConcursos"]},{"@type":"Person","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/b4a388c97673c5f483d72185668afa1f","name":"Coordena\u00e7\u00e3o","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/b720319e4c9a967eb58678d110f4fe35452fc5d5f97b202bac7b8acceb18c6ad?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b720319e4c9a967eb58678d110f4fe35452fc5d5f97b202bac7b8acceb18c6ad?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b720319e4c9a967eb58678d110f4fe35452fc5d5f97b202bac7b8acceb18c6ad?s=96&d=mm&r=g","caption":"Coordena\u00e7\u00e3o"},"sameAs":["https:\/\/www.facebook.com\/EstrategiaConcursos","https:\/\/x.com\/EstratConcursos"],"url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/estrategia2013\/"}]}},"_links":{"self":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/836144","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/comments?post=836144"}],"version-history":[{"count":4,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/836144\/revisions"}],"predecessor-version":[{"id":836297,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/836144\/revisions\/836297"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media\/740957"}],"wp:attachment":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media?parent=836144"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/categories?post=836144"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tags?post=836144"},{"taxonomy":"tax_estado","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tax_estado?post=836144"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}