{"id":835841,"date":"2021-08-13T16:53:26","date_gmt":"2021-08-13T19:53:26","guid":{"rendered":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?p=835841"},"modified":"2021-08-13T16:53:27","modified_gmt":"2021-08-13T19:53:27","slug":"concurso-guarda-de-campo-grande-retomado","status":"publish","type":"post","link":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-guarda-de-campo-grande-retomado\/","title":{"rendered":"Concurso Guarda de Campo Grande \u00e9 RETOMADO!"},"content":{"rendered":"\n<p>Foi retomado o <strong>concurso p\u00fablico da Guarda de Campo Grande<\/strong>, no estado de Mato Grosso do Sul, que estava suspenso por conta da pandemia da Covid-19.<\/p>\n\n\n\n<p>Agora, segundo o documento, a prova ser\u00e1 aplicada na data prov\u00e1vel de <strong>19 de setembro de 2021<\/strong>. Os locais de provas, bem como hor\u00e1rios e informa\u00e7\u00f5es relevantes, ser\u00e3o publicados no dia 15 de setembro, no site da banca organizadora, o Instituto Selecon. Veja o documento na \u00edntegra:<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/08\/13155107\/frfrfrgd-1.png\" alt=\"\" class=\"wp-image-835756\" width=\"570\" height=\"585\" srcset=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/08\/13155107\/frfrfrgd-1.png 628w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/08\/13155107\/frfrfrgd-1-292x300.png 292w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/08\/13155107\/frfrfrgd-1-610x627.png 610w\" sizes=\"auto, (max-width: 570px) 100vw, 570px\" \/><\/figure><\/div>\n\n\n\n<p> O certame oferta aos candidatos <strong>273 vagas <\/strong>imediatas para n\u00edvel m\u00e9dio. O sal\u00e1rio inicial \u00e9 de R$ 1.690,02, sem contar as gratifica\u00e7\u00f5es e benef\u00edcios.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-estrutura-remunerat-ria-concurso-guarda-de-campo-grande-retomdo\">Estrutura Remunerat\u00f3ria &#8211; concurso Guarda de Campo Grande \u00e9 RETOMDO<\/h3>\n\n\n\n<p>O ingresso no cargo da Guarda Civil Metropolitano dar-se-\u00e1 na Terceira Classe da carreira.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"974\" height=\"342\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2019\/08\/30154611\/image121.png\" alt=\"Concurso Guarda Municipal Campo Grande: estrutura remunerat\u00f3ria\" class=\"wp-image-414719\" srcset=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2019\/08\/30154611\/image121.png 974w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2019\/08\/30154611\/image121.png 300w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2019\/08\/30154611\/image121.png 768w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2019\/08\/30154611\/image121.png 610w\" sizes=\"auto, (max-width: 974px) 100vw, 974px\" \/><figcaption>Concurso Guarda Municipal Campo Grande: estrutura remunerat\u00f3ria<\/figcaption><\/figure>\n\n\n\n<p>Para mais informa\u00e7\u00f5es do concurso <a href=\"http:\/\/www.campogrande.ms.gov.br\/cgnoticias\/noticias\/prefeitura-anuncia-nova-data-da-prova-objetiva-do-concurso-publico-da-guarda-civil-metropolitana\/\" target=\"_blank\" rel=\"noreferrer noopener\">Guarda de Campo Grande<\/a>, agora oficialmente retomado, acesse o link abaixo! Preparamos um artigo completo para voc\u00ea!<\/p>\n\n\n\n<p class=\"has-text-align-center has-background\" style=\"background-color:#a9bac2;font-size:clamp(14.642px, 0.915rem + ((1vw - 3.2px) * 0.721), 22px);px\"><strong><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-guarda-municipal-campo-grande\/\" target=\"_blank\" rel=\"noreferrer noopener\">Concurso Guarda de Campo Grande<\/a><\/strong><\/p>\n\n\n\n<h2 class=\"has-text-align-center wp-block-heading\">Quer estudar para o concurso Guarda de Campo Grande MS?<\/h2>\n\n\n\n<div id=\"boxes\" class=\"container\">\n<div class=\"row\">\n<div class=\"col-sm\">\n<div id=\"box-assinatura\" class=\"banner-policial\">\n<h3 class=\"titulo-assinatura\">Concurso Guarda de Campo Grande<\/h3>\n<p class=\"subtitulo-assinatura\">Conhe\u00e7a os cursos<\/p>\n<div class=\"box-botao\"><a class=\"btn-assinatura\" role=\"button\" href=\"https:\/\/www.estrategiaconcursos.com.br\/curso\/pacote-completo-p-prefeitura-de-campo-grande-ms-guarda-municipal-pre-edital\/\" target=\"_blank\" rel=\"noopener noreferrer\">Conhe\u00e7a mais<\/a><\/div>\n<\/div>\n<p class=\"texto-auxiliar\"><\/p>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"container\" id=\"boxes\">\n  <div class=\"row\">\n\n    <div class=\"col-sm\">\n      <div class=\"estrategia\" id=\"box-assinatura\">\n        <h3 class=\"titulo-assinatura\">Assinatura Concursos<\/h3>\n        <p class=\"subtitulo-assinatura\">Assinatura de 1 ano ou 2 anos<\/p>\n        <div class=\"box-botao\">\n          <a class=\"btn-assinatura\" target=\"_blank\" href=\"https:\/\/www.estrategiaconcursos.com.br\/assinaturas\/\" role=\"button\" rel=\"noopener noreferrer\">ASSINE AGORA<\/a>\n        <\/div>\n      <\/div>\n     \n    <\/div><\/div><\/div>\n\n\n\n<div class=\"container\" id=\"boxes\">\n  <div class=\"row\">\n\n    <div class=\"col-sm\" id=\"boxes-concursos\">\n      <div style=\"background-color: #005DAD;\" class=\"conteudo-concursos\" id=\"box-concursos\">\n        <h3 class=\"titulo-assinatura\">Concursos Abertos<\/h3>\n        <p class=\"subtitulo-assinatura\">Os editais publicados<\/p>\n        <div class=\"box-botao\">\n          <a class=\"btn-assinatura\" target=\"_blank\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-abertos\/\" role=\"button\" rel=\"noopener noreferrer\">Conhe\u00e7a Agora<\/a>\n        <\/div>\n      <\/div>\n    <\/div>\n\n    <div class=\"col-sm\" id=\"boxes-concursos\">\n      <div style=\"background-color: #1A7ED5;\" class=\"conteudo-concursos\" id=\"box-concursos\">\n        <h3 class=\"titulo-assinatura\">Concursos 2021<\/h3>\n        <p class=\"subtitulo-assinatura\">As oportunidades previstas<\/p>\n        <div class=\"box-botao\">\n          <a class=\"btn-assinatura\" target=\"_blank\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-2021\/\" role=\"button\" rel=\"noopener noreferrer\">Conhe\u00e7a Agora<\/a>\n        <\/div>\n      <\/div>\n    <\/div>\n\n    <div class=\"col-sm\" id=\"boxes-concursos\">\n      <div style=\"background-color: #419FF0;\" class=\"conteudo-concursos\" id=\"box-concursos\">\n        <h3 class=\"titulo-assinatura\">Concursos 2022<\/h3>\n        <p class=\"subtitulo-assinatura\">Vagas para o pr\u00f3ximo ano<\/p>\n        <div class=\"box-botao\">\n          <a class=\"btn-assinatura\" target=\"_blank\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-2022\/\" role=\"button\" rel=\"noopener noreferrer\">Conhe\u00e7a Agora<\/a>\n        <\/div>\n      <\/div>\n    <\/div>\n\n  <\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Foi retomado o concurso p\u00fablico da Guarda de Campo Grande, no estado de Mato Grosso do Sul, que estava suspenso por conta da pandemia da Covid-19. Agora, segundo o documento, a prova ser\u00e1 aplicada na data prov\u00e1vel de 19 de setembro de 2021. Os locais de provas, bem como hor\u00e1rios e informa\u00e7\u00f5es relevantes, ser\u00e3o publicados [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":621479,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"post_tipo":"news","footnotes":""},"categories":[220189],"tags":[],"tax_estado":[219975],"class_list":["post-835841","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-policial-guarda-civis","tax_estado-ms"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.2 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Concurso Guarda de Campo Grande \u00e9 RETOMADO!<\/title>\n<meta name=\"description\" content=\"Foi retomado o concurso p\u00fablico da Guarda de Campo Grande, no estado de Mato Grosso do Sul, que estava suspenso por conta da Covid-19.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-guarda-de-campo-grande-retomado\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Concurso Guarda de Campo Grande \u00e9 RETOMADO!\" \/>\n<meta property=\"og:description\" content=\"Foi retomado o concurso p\u00fablico da Guarda de Campo Grande, no estado de Mato Grosso do Sul, que estava suspenso por conta da Covid-19.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-guarda-de-campo-grande-retomado\/\" \/>\n<meta property=\"og:site_name\" content=\"Estrat\u00e9gia Concursos\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/EstrategiaConcursos\" \/>\n<meta property=\"article:published_time\" content=\"2021-08-13T19:53:26+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-08-13T19:53:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/12\/02134741\/Guarda-Municipal-Campo-Grande.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"628\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Coordena\u00e7\u00e3o\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:site\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Coordena\u00e7\u00e3o\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-guarda-de-campo-grande-retomado\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-guarda-de-campo-grande-retomado\/\"},\"author\":{\"name\":\"Coordena\u00e7\u00e3o\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/b4a388c97673c5f483d72185668afa1f\"},\"headline\":\"Concurso Guarda de Campo Grande \u00e9 RETOMADO!\",\"datePublished\":\"2021-08-13T19:53:26+00:00\",\"dateModified\":\"2021-08-13T19:53:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-guarda-de-campo-grande-retomado\/\"},\"wordCount\":223,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-guarda-de-campo-grande-retomado\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/12\/02134741\/Guarda-Municipal-Campo-Grande.jpg\",\"articleSection\":[\"Policial (Guardas Civis)\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-guarda-de-campo-grande-retomado\/#respond\"]}],\"copyrightYear\":\"2021\",\"copyrightHolder\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-guarda-de-campo-grande-retomado\/\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-guarda-de-campo-grande-retomado\/\",\"name\":\"Concurso Guarda de Campo Grande \u00e9 RETOMADO!\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-guarda-de-campo-grande-retomado\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-guarda-de-campo-grande-retomado\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/12\/02134741\/Guarda-Municipal-Campo-Grande.jpg\",\"datePublished\":\"2021-08-13T19:53:26+00:00\",\"dateModified\":\"2021-08-13T19:53:27+00:00\",\"description\":\"Foi retomado o concurso p\u00fablico da Guarda de Campo Grande, no estado de Mato Grosso do Sul, que estava suspenso por conta da Covid-19.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-guarda-de-campo-grande-retomado\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-guarda-de-campo-grande-retomado\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-guarda-de-campo-grande-retomado\/#primaryimage\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/12\/02134741\/Guarda-Municipal-Campo-Grande.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/12\/02134741\/Guarda-Municipal-Campo-Grande.jpg\",\"width\":1200,\"height\":628,\"caption\":\"guarda campo grande\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-guarda-de-campo-grande-retomado\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Concurso Guarda de Campo Grande \u00e9 RETOMADO!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"name\":\"Estrat\u00e9gia Concursos\",\"description\":\"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.\",\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\",\"name\":\"Estrat\u00e9gia Concursos\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"width\":230,\"height\":60,\"caption\":\"Estrat\u00e9gia Concursos\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/EstratConcursos\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/b4a388c97673c5f483d72185668afa1f\",\"name\":\"Coordena\u00e7\u00e3o\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/b720319e4c9a967eb58678d110f4fe35452fc5d5f97b202bac7b8acceb18c6ad?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/b720319e4c9a967eb58678d110f4fe35452fc5d5f97b202bac7b8acceb18c6ad?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/b720319e4c9a967eb58678d110f4fe35452fc5d5f97b202bac7b8acceb18c6ad?s=96&d=mm&r=g\",\"caption\":\"Coordena\u00e7\u00e3o\"},\"sameAs\":[\"https:\/\/www.facebook.com\/EstrategiaConcursos\",\"https:\/\/x.com\/EstratConcursos\"],\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/estrategia2013\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Concurso Guarda de Campo Grande \u00e9 RETOMADO!","description":"Foi retomado o concurso p\u00fablico da Guarda de Campo Grande, no estado de Mato Grosso do Sul, que estava suspenso por conta da Covid-19.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-guarda-de-campo-grande-retomado\/","og_locale":"pt_BR","og_type":"article","og_title":"Concurso Guarda de Campo Grande \u00e9 RETOMADO!","og_description":"Foi retomado o concurso p\u00fablico da Guarda de Campo Grande, no estado de Mato Grosso do Sul, que estava suspenso por conta da Covid-19.","og_url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-guarda-de-campo-grande-retomado\/","og_site_name":"Estrat\u00e9gia Concursos","article_author":"https:\/\/www.facebook.com\/EstrategiaConcursos","article_published_time":"2021-08-13T19:53:26+00:00","article_modified_time":"2021-08-13T19:53:27+00:00","og_image":[{"width":1200,"height":628,"url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/12\/02134741\/Guarda-Municipal-Campo-Grande.jpg","type":"image\/jpeg"}],"author":"Coordena\u00e7\u00e3o","twitter_card":"summary_large_image","twitter_creator":"@EstratConcursos","twitter_site":"@EstratConcursos","twitter_misc":{"Escrito por":"Coordena\u00e7\u00e3o","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-guarda-de-campo-grande-retomado\/#article","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-guarda-de-campo-grande-retomado\/"},"author":{"name":"Coordena\u00e7\u00e3o","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/b4a388c97673c5f483d72185668afa1f"},"headline":"Concurso Guarda de Campo Grande \u00e9 RETOMADO!","datePublished":"2021-08-13T19:53:26+00:00","dateModified":"2021-08-13T19:53:27+00:00","mainEntityOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-guarda-de-campo-grande-retomado\/"},"wordCount":223,"commentCount":0,"publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-guarda-de-campo-grande-retomado\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/12\/02134741\/Guarda-Municipal-Campo-Grande.jpg","articleSection":["Policial (Guardas Civis)"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-guarda-de-campo-grande-retomado\/#respond"]}],"copyrightYear":"2021","copyrightHolder":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-guarda-de-campo-grande-retomado\/","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-guarda-de-campo-grande-retomado\/","name":"Concurso Guarda de Campo Grande \u00e9 RETOMADO!","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-guarda-de-campo-grande-retomado\/#primaryimage"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-guarda-de-campo-grande-retomado\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/12\/02134741\/Guarda-Municipal-Campo-Grande.jpg","datePublished":"2021-08-13T19:53:26+00:00","dateModified":"2021-08-13T19:53:27+00:00","description":"Foi retomado o concurso p\u00fablico da Guarda de Campo Grande, no estado de Mato Grosso do Sul, que estava suspenso por conta da Covid-19.","breadcrumb":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-guarda-de-campo-grande-retomado\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-guarda-de-campo-grande-retomado\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-guarda-de-campo-grande-retomado\/#primaryimage","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/12\/02134741\/Guarda-Municipal-Campo-Grande.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/12\/02134741\/Guarda-Municipal-Campo-Grande.jpg","width":1200,"height":628,"caption":"guarda campo grande"},{"@type":"BreadcrumbList","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-guarda-de-campo-grande-retomado\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.estrategiaconcursos.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Concurso Guarda de Campo Grande \u00e9 RETOMADO!"}]},{"@type":"WebSite","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","name":"Estrat\u00e9gia Concursos","description":"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.","publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization","name":"Estrat\u00e9gia Concursos","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","width":230,"height":60,"caption":"Estrat\u00e9gia Concursos"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/EstratConcursos"]},{"@type":"Person","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/b4a388c97673c5f483d72185668afa1f","name":"Coordena\u00e7\u00e3o","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/b720319e4c9a967eb58678d110f4fe35452fc5d5f97b202bac7b8acceb18c6ad?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b720319e4c9a967eb58678d110f4fe35452fc5d5f97b202bac7b8acceb18c6ad?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b720319e4c9a967eb58678d110f4fe35452fc5d5f97b202bac7b8acceb18c6ad?s=96&d=mm&r=g","caption":"Coordena\u00e7\u00e3o"},"sameAs":["https:\/\/www.facebook.com\/EstrategiaConcursos","https:\/\/x.com\/EstratConcursos"],"url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/estrategia2013\/"}]}},"_links":{"self":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/835841","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/comments?post=835841"}],"version-history":[{"count":4,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/835841\/revisions"}],"predecessor-version":[{"id":835847,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/835841\/revisions\/835847"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media\/621479"}],"wp:attachment":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media?parent=835841"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/categories?post=835841"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tags?post=835841"},{"taxonomy":"tax_estado","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tax_estado?post=835841"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}