{"id":8233,"date":"2016-06-21T04:00:05","date_gmt":"2016-06-21T07:00:05","guid":{"rendered":"https:\/\/www.estrategiaconcursos.com.br\/blog\/principio-da-congruencia-4\/"},"modified":"2016-12-12T11:08:16","modified_gmt":"2016-12-12T14:08:16","slug":"principio-da-congruencia-4","status":"publish","type":"post","link":"https:\/\/www.estrategiaconcursos.com.br\/blog\/principio-da-congruencia-4\/","title":{"rendered":"Princ\u00edpio da Congru\u00eancia &#8211; Atualizado conforme Novo CPC"},"content":{"rendered":"<div style=\"text-align: justify\">\n<p><strong>Confira o Princ\u00edpio da Congru\u00eancia, atualizado conforme Novo CPC (C\u00f3digo de Processo Civil de 2015)<\/strong><\/p>\n<p><span style=\"font-family: Verdana\">Ol\u00e1 pessoal, firmes e fortes nos estudos? Hoje falaremos um pouco do <em><strong><span style=\"color: #0000ff\"><u>Princ\u00edpio da Congru\u00eancia<\/u><\/span><\/strong>.<\/em><\/span><\/p>\n<\/div>\n<div style=\"text-align: justify\">\n<p class=\"Artigo\" align=\"justify\"><b>Sobre o princ\u00edpio da congru\u00eancia (ou adstri\u00e7\u00e3o)&#8230; conv\u00e9m lermos o seguinte d<\/b><b>ispositivo do CPC\/2015:<\/b><\/p>\n<p class=\"Artigo\" align=\"justify\"><em>Art. 492. \u00a0\u00c9 vedado ao juiz proferir decis\u00e3o de natureza diversa da pedida, bem como condenar a parte em quantidade superior ou em objeto diverso do que lhe foi demandado.<\/em><\/p>\n<p class=\"Artigo\" align=\"justify\"><em>Par\u00e1grafo \u00fanico. \u00a0A decis\u00e3o deve ser certa, ainda que resolva rela\u00e7\u00e3o jur\u00eddica condicional.<\/em><\/p>\n<p>&nbsp;<\/p>\n<p>O princ\u00edpio da congru\u00eancia trata de uma proibi\u00e7\u00e3o ao magistrado.<\/p>\n<p>N\u00e3o poder\u00e1 o juiz conceder <b>nada a mais (<em>ultra petita<\/em>) ou diferente do que foi pedido (<em>extra petita<\/em>).<\/b><\/p>\n<p>Assim, como n\u00e3o poder\u00e1 fundamentar-se em causa de pedir diferente da narrada pelo autor; caso n\u00e3o seja observado esse princ\u00edpio a senten\u00e7a ser\u00e1 considerada nula.<\/p>\n<p>Existem <strong><span style=\"color: #ff0000\">exce\u00e7\u00f5es<\/span><\/strong>, previstas em Lei, ao princ\u00edpio da congru\u00eancia.<\/p>\n<p><strong>1)<\/strong> Pedidos impl\u00edcitos: o magistrado poder\u00e1 conceder o que n\u00e3o foi demando pelo autor.<\/p>\n<p><strong>2)<\/strong> Fungibilidade: o magistrado poder\u00e1 conceder tutela diferente da requerida nas a\u00e7\u00f5es possess\u00f3rias e cautelares.<\/p>\n<p><strong>3)<\/strong> Demandas cujo objetivo \u00e9 uma obriga\u00e7\u00e3o de fazer ou n\u00e3o fazer: o magistrado poder\u00e1 conceder tutela diversa.<\/p>\n<p><strong>4) <\/strong>O Supremo Tribunal Federal tamb\u00e9m admite o afastamento do princ\u00edpio da congru\u00eancia ao declarar inconstitucionalidade de uma norma, em aten\u00e7\u00e3o a pedido formulado pelo autor, todavia, utilizando-se de fundamentos diferentes daqueles que foram suscitados.<\/p>\n<p><strong>D\u00favida:<\/strong> O Supremo pode, portanto, declarar a inconstitucionalidade de uma norma com fundamento distinto do que foi suscitado pelo autor?<\/p>\n<p><strong>Resposta:<\/strong> Pode sim. Exatamente. Nesse sentido h\u00e1 esta decis\u00e3o do STF:<\/p>\n<p>\u201c\u00c9 da jurisprud\u00eancia do Plen\u00e1rio, o entendimento de que, na a\u00e7\u00e3o direta de inconstitucionalidade, seu julgamento independe da causa petendi formulada na inicial, ou seja, dos fundamentos jur\u00eddicos nela deduzidos, pois, havendo, nesse processo objetivo, argui\u00e7\u00e3o de inconstitucionalidade, a Corte deve consider\u00e1-la sob todos os aspectos em face da Constitui\u00e7\u00e3o e n\u00e3o apenas diante daqueles focalizados pelo autor. \u00c9 de se presumir, ent\u00e3o, que, no precedente, ao menos implicitamente, hajam sido considerados quaisquer fundamentos para eventual argui\u00e7\u00e3o de inconstitucionalidade, inclusive os apresentados na inicial da presente a\u00e7\u00e3o.&#8221; <b>(ADI 1.896-MC, Rel. Min. Sydney Sanches, julgamento em 18-2-99, DJ de 28-5-99)<br \/>\n<\/b><\/p>\n<\/div>\n<p><strong>Indo al\u00e9m&#8230;<\/strong><\/p>\n<p class=\"Artigo\" align=\"justify\">\u00c9 correto considerar que o princ\u00edpio assumiu uma dimens\u00e3o flex\u00edvel no C\u00f3digo de Processo Civil de 2015, verific\u00e1vel na disposi\u00e7\u00e3o inovadora do par\u00e1grafo 2\u00ba do artigo 322, que veio a considerar que<span style=\"color: #0000ff\"><strong> a interpreta\u00e7\u00e3o do pedid<span style=\"color: #0000ff\">o<\/span> considerar\u00e1 o conjunto da postula\u00e7\u00e3o e observar\u00e1 o princ\u00edpio da boa-f\u00e9<\/strong><\/span>. No c\u00f3digo anterior (de 1973), a previs\u00e3o era de que a interpreta\u00e7\u00e3o deveria ser restritiva.<\/p>\n<p class=\"Artigo\" align=\"justify\">A novidade segue a tend\u00eancia de se atribuir maior envergadura ao princ\u00edpio da boa-f\u00e9 e maior autonomia aos sujeitos do processo, incluindo-se o juiz, em busca da efetiva presta\u00e7\u00e3o jurisdicional.<\/p>\n<p class=\"Artigo\" align=\"justify\">Da entrada em vigor do CPC\/2015 em diante, o princ\u00edpio da congru\u00eancia tornou-se mais flex\u00edvel, uma vez que se passou a admitir uma interpreta\u00e7\u00e3o do pedido pelo juiz com grau de subjetividade maior do que se reconhecia no sistema do c\u00f3digo anterior.<\/p>\n<div style=\"text-align: justify\">\n<p>Isso a\u00ed meus amigos, n\u00e3o \u00e9 nenhum \u201cbicho de sete cabe\u00e7as\u201d. Constantemente h\u00e1 d\u00favidas acerca desse princ\u00edpio, principalmente em rela\u00e7\u00e3o \u00e0 \u00faltima exce\u00e7\u00e3o.<\/p>\n<\/div>\n<p><iframe loading=\"lazy\" title=\"Grafico principio da conguencia\" src=\"https:\/\/www.slideshare.net\/slideshow\/embed_code\/key\/xPxjKUOP3XiLm\" width=\"479\" height=\"511\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\" style=\"border:1px solid #CCC; border-width:1px; margin-bottom:5px; max-width: 100%;\" allowfullscreen> <\/iframe> <\/p>\n<div style=\"margin-bottom:5px\"> <strong> <a href=\"https:\/\/pt.slideshare.net\/ProfessorGabrielBorges\/grafico-principio-da-conguencia\" title=\"Grafico principio da conguencia\" target=\"_blank\">Grafico principio da conguencia<\/a> <\/strong> from <strong><a href=\"https:\/\/www.slideshare.net\/ProfessorGabrielBorges\" target=\"_blank\">Professor Gabriel Borges<\/a><\/strong> <\/div>\n<div style=\"text-align: justify\">\n<p>Aproveito para inform\u00e1-los que estamos com v\u00e1rios cursos dispon\u00edveis para voc\u00eas.<\/p>\n<p>Clique <a href=\"https:\/\/www.estrategiaconcursos.com.br\/cursosPorProfessor\/gabriel-borges-3201\/\">aqui<\/a> ou neste <a href=\"https:\/\/www.estrategiaconcursos.com.br\/cursosPorProfessor\/gabriel-borges-3201\/\">link<\/a> e confira!<\/p>\n<p>Abra\u00e7os e bons estudos,<\/p>\n<p>Prof. Gabriel Borges<\/p>\n<\/div>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Confira o Princ\u00edpio da Congru\u00eancia, atualizado conforme Novo CPC (C\u00f3digo de Processo Civil de 2015) Ol\u00e1 pessoal, firmes e fortes nos estudos? Hoje falaremos um pouco do Princ\u00edpio da Congru\u00eancia. Sobre o princ\u00edpio da congru\u00eancia (ou adstri\u00e7\u00e3o)&#8230; conv\u00e9m lermos o seguinte dispositivo do CPC\/2015: Art. 492. \u00a0\u00c9 vedado ao juiz proferir decis\u00e3o de natureza diversa [&hellip;]<\/p>\n","protected":false},"author":32,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"post_tipo":"article","footnotes":""},"categories":[1,1988],"tags":[1107,1883,1182],"tax_estado":[],"class_list":["post-8233","post","type-post","status-publish","format-standard","hentry","category-cursos-e-concursos","category-policia","tag-novo-cpc","tag-principio-da-congruencia","tag-processo-civil"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.2 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Princ\u00edpio da Congru\u00eancia - Atualizado conforme Novo CPC<\/title>\n<meta name=\"description\" content=\"Princ\u00edpio da Congru\u00eancia - Atualizado conforme Novo CPC\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/principio-da-congruencia-4\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Princ\u00edpio da Congru\u00eancia - Atualizado conforme Novo CPC\" \/>\n<meta property=\"og:description\" content=\"Princ\u00edpio da Congru\u00eancia - Atualizado conforme Novo CPC\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/principio-da-congruencia-4\/\" \/>\n<meta property=\"og:site_name\" content=\"Estrat\u00e9gia Concursos\" \/>\n<meta property=\"article:author\" content=\"facebook.com\/professorgabrielborges\" \/>\n<meta property=\"article:published_time\" content=\"2016-06-21T07:00:05+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-12-12T14:08:16+00:00\" \/>\n<meta name=\"author\" content=\"Gabriel Borges\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:site\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gabriel Borges\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/principio-da-congruencia-4\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/principio-da-congruencia-4\/\"},\"author\":{\"name\":\"Gabriel Borges\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/9e5c3c1435570e992b72a04cf1b37243\"},\"headline\":\"Princ\u00edpio da Congru\u00eancia &#8211; Atualizado conforme Novo CPC\",\"datePublished\":\"2016-06-21T07:00:05+00:00\",\"dateModified\":\"2016-12-12T14:08:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/principio-da-congruencia-4\/\"},\"wordCount\":630,\"commentCount\":4,\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"keywords\":[\"Novo CPC\",\"Princ\u00edpio da Congru\u00eancia\",\"Processo Civil\"],\"articleSection\":[\"Concursos P\u00fablicos\",\"Policial (Agente, Escriv\u00e3o e Investigador)\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/principio-da-congruencia-4\/#respond\"]}],\"copyrightYear\":\"2016\",\"copyrightHolder\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/principio-da-congruencia-4\/\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/principio-da-congruencia-4\/\",\"name\":\"Princ\u00edpio da Congru\u00eancia - Atualizado conforme Novo CPC\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\"},\"datePublished\":\"2016-06-21T07:00:05+00:00\",\"dateModified\":\"2016-12-12T14:08:16+00:00\",\"description\":\"Princ\u00edpio da Congru\u00eancia - Atualizado conforme Novo CPC\",\"breadcrumb\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/principio-da-congruencia-4\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/principio-da-congruencia-4\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/principio-da-congruencia-4\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Princ\u00edpio da Congru\u00eancia &#8211; Atualizado conforme Novo CPC\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"name\":\"Estrat\u00e9gia Concursos\",\"description\":\"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.\",\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\",\"name\":\"Estrat\u00e9gia Concursos\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"width\":230,\"height\":60,\"caption\":\"Estrat\u00e9gia Concursos\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/EstratConcursos\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/9e5c3c1435570e992b72a04cf1b37243\",\"name\":\"Gabriel Borges\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/be2799aa77611ff8261d7ed48aabeba33838bc6bc219cd46d9fa887b983110ea?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/be2799aa77611ff8261d7ed48aabeba33838bc6bc219cd46d9fa887b983110ea?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/be2799aa77611ff8261d7ed48aabeba33838bc6bc219cd46d9fa887b983110ea?s=96&d=mm&r=g\",\"caption\":\"Gabriel Borges\"},\"sameAs\":[\"facebook.com\/professorgabrielborges\"],\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/gabrielborgesestrategiaconcursos-com-br\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Princ\u00edpio da Congru\u00eancia - Atualizado conforme Novo CPC","description":"Princ\u00edpio da Congru\u00eancia - Atualizado conforme Novo CPC","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.estrategiaconcursos.com.br\/blog\/principio-da-congruencia-4\/","og_locale":"pt_BR","og_type":"article","og_title":"Princ\u00edpio da Congru\u00eancia - Atualizado conforme Novo CPC","og_description":"Princ\u00edpio da Congru\u00eancia - Atualizado conforme Novo CPC","og_url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/principio-da-congruencia-4\/","og_site_name":"Estrat\u00e9gia Concursos","article_author":"facebook.com\/professorgabrielborges","article_published_time":"2016-06-21T07:00:05+00:00","article_modified_time":"2016-12-12T14:08:16+00:00","author":"Gabriel Borges","twitter_card":"summary_large_image","twitter_creator":"@EstratConcursos","twitter_site":"@EstratConcursos","twitter_misc":{"Escrito por":"Gabriel Borges","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/principio-da-congruencia-4\/#article","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/principio-da-congruencia-4\/"},"author":{"name":"Gabriel Borges","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/9e5c3c1435570e992b72a04cf1b37243"},"headline":"Princ\u00edpio da Congru\u00eancia &#8211; Atualizado conforme Novo CPC","datePublished":"2016-06-21T07:00:05+00:00","dateModified":"2016-12-12T14:08:16+00:00","mainEntityOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/principio-da-congruencia-4\/"},"wordCount":630,"commentCount":4,"publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"keywords":["Novo CPC","Princ\u00edpio da Congru\u00eancia","Processo Civil"],"articleSection":["Concursos P\u00fablicos","Policial (Agente, Escriv\u00e3o e Investigador)"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/principio-da-congruencia-4\/#respond"]}],"copyrightYear":"2016","copyrightHolder":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/principio-da-congruencia-4\/","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/principio-da-congruencia-4\/","name":"Princ\u00edpio da Congru\u00eancia - Atualizado conforme Novo CPC","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website"},"datePublished":"2016-06-21T07:00:05+00:00","dateModified":"2016-12-12T14:08:16+00:00","description":"Princ\u00edpio da Congru\u00eancia - Atualizado conforme Novo CPC","breadcrumb":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/principio-da-congruencia-4\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/principio-da-congruencia-4\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/principio-da-congruencia-4\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.estrategiaconcursos.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Princ\u00edpio da Congru\u00eancia &#8211; Atualizado conforme Novo CPC"}]},{"@type":"WebSite","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","name":"Estrat\u00e9gia Concursos","description":"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.","publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization","name":"Estrat\u00e9gia Concursos","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","width":230,"height":60,"caption":"Estrat\u00e9gia Concursos"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/EstratConcursos"]},{"@type":"Person","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/9e5c3c1435570e992b72a04cf1b37243","name":"Gabriel Borges","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/be2799aa77611ff8261d7ed48aabeba33838bc6bc219cd46d9fa887b983110ea?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/be2799aa77611ff8261d7ed48aabeba33838bc6bc219cd46d9fa887b983110ea?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/be2799aa77611ff8261d7ed48aabeba33838bc6bc219cd46d9fa887b983110ea?s=96&d=mm&r=g","caption":"Gabriel Borges"},"sameAs":["facebook.com\/professorgabrielborges"],"url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/gabrielborgesestrategiaconcursos-com-br\/"}]}},"_links":{"self":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/8233","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/users\/32"}],"replies":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/comments?post=8233"}],"version-history":[{"count":8,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/8233\/revisions"}],"predecessor-version":[{"id":57625,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/8233\/revisions\/57625"}],"wp:attachment":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media?parent=8233"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/categories?post=8233"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tags?post=8233"},{"taxonomy":"tax_estado","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tax_estado?post=8233"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}