{"id":786228,"date":"2021-07-07T13:59:37","date_gmt":"2021-07-07T16:59:37","guid":{"rendered":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?p=786228"},"modified":"2021-07-07T14:00:11","modified_gmt":"2021-07-07T17:00:11","slug":"conciliar-banco-do-brasil-tj-sp","status":"publish","type":"post","link":"https:\/\/www.estrategiaconcursos.com.br\/blog\/conciliar-banco-do-brasil-tj-sp\/","title":{"rendered":"Banco do Brasil e TJ-SP: \u00c9 poss\u00edvel conciliar os estudos?"},"content":{"rendered":"\n<p class=\"has-medium-font-size\">Veja neste artigo sobre as possibilidades de conciliar os estudos para os concursos do&nbsp;<strong><a href=\"https:\/\/www.estrategiaconcursos.com.br\/cursosPorConcurso\/banco-do-brasil-escriturario-99\/\" target=\"_blank\" rel=\"noreferrer noopener\">Banco do Brasil<\/a><\/strong>&nbsp;e do <strong><a href=\"https:\/\/www.estrategiaconcursos.com.br\/curso\/1-pacote-completo-p-tj-sp-escrevente-judiciario-2021-pre-edital\/\" target=\"_blank\" rel=\"noreferrer noopener\">TJ-SP<\/a><\/strong>.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"374\" height=\"412\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/07\/04113121\/image-133.png\" alt=\"Conciliar Banco do Brasil e TJ-SP\" class=\"wp-image-786243\" srcset=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/07\/04113121\/image-133.png 374w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/07\/04113121\/image-133-272x300.png 272w\" sizes=\"auto, (max-width: 374px) 100vw, 374px\" \/><figcaption>Conciliar Banco do Brasil e TJ-SP<\/figcaption><\/figure><\/div>\n\n\n\n<p>Ol\u00e1, pessoal! Tudo bem com voc\u00eas?<\/p>\n\n\n\n<p><strong>O segundo semestre de 2021 est\u00e1 com tudo na \u00e1rea dos concursos.<\/strong>&nbsp;Dezenas de provas que ficaram represadas durante mais de um ano de pandemia est\u00e3o saindo agora, quase que simultaneamente, al\u00e9m de dezenas de outras que est\u00e3o pr\u00f3ximas de terem seus editais publicados.<\/p>\n\n\n\n<p>Um dos concursos que teve seu&nbsp;<strong>edital&nbsp;<\/strong>lan\u00e7ado recentemente foi o&nbsp;<strong><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-banco-do-brasil-2\/\" target=\"_blank\" rel=\"noreferrer noopener\">Banco do Brasil<\/a><\/strong>, provocando uma grande euforia em toda a na\u00e7\u00e3o concurseira.<\/p>\n\n\n\n<p>Outro certame, o qual ainda n\u00e3o est\u00e1 aberto, mas possui&nbsp;<strong>grandes chances de ter seu edital publicado ainda este ano \u00e9 o concurso do Tribunal de Justi\u00e7a de S\u00e3o Paulo, o <a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-tj-sp-2021\/\" target=\"_blank\" rel=\"noreferrer noopener\">TJ-SP<\/a>.<\/strong> De acordo com o pr\u00f3prio presidente do tribunal, j\u00e1 h\u00e1 uma grande movimenta\u00e7\u00e3o para que este certame tenha sua prova aplicada em 2021.<\/p>\n\n\n\n<p>Diante deste cen\u00e1rio, fica a quest\u00e3o:&nbsp;<strong><span class=\"has-inline-color has-vivid-cyan-blue-color\">Em qual certame focar? \u00c9 poss\u00edvel conciliar os estudos para essa grande quantidade de concursos, principalmente para o Banco do Brasil e TJ-SP?<\/span><\/strong><\/p>\n\n\n\n<p>N\u00e3o se desespere, pois estamos aqui justamente para ajud\u00e1-lo a sair deste grande dilema. Assim, preparamos este artigo para discutir sobre a possibilidade de concilia\u00e7\u00e3o dos estudos para este certame, o qual dividiremos da seguinte maneira:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>Cargos e Quantidade de Vagas;<\/strong><\/li><li><strong>Remunera\u00e7\u00e3o;<\/strong><\/li><li><strong>Hist\u00f3rico de Estudo;<\/strong><\/li><li><strong>Disciplinas;<\/strong><\/li><li><strong>Aulas do Estrat\u00e9gia Concursos.<\/strong><\/li><\/ul>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-cargos-e-quantidade-de-vagas\">Cargos e Quantidade de Vagas<\/h2>\n\n\n\n<p>Para iniciarmos o nosso estudo sobre a possibilidade de <strong>conciliar <\/strong>os estudos para os concursos do <strong>Banco do Brasil<\/strong> e do <strong>TJ-SP<\/strong>, iremos analisar os cargos e vagas que ser\u00e3o ofertados.<\/p>\n\n\n\n<p>O quantitativo de&nbsp;<strong>vagas ofertadas&nbsp;<\/strong>\u00e9 um importante item a ser levado em considera\u00e7\u00e3o ao tentar conciliar os estudos em mais de um concurso, isso porque,<strong>&nbsp;se houver muitas vagas em ambos, as chances de conciliar aumentam.<\/strong><\/p>\n\n\n\n<p>Para o concurso do&nbsp;<strong>Banco do Brasil<\/strong>, o qual teve edital publicado recentemente, h\u00e1 a oferta de&nbsp;<strong>4.480 vagas<\/strong>, sendo 2.240 diretas e mais 2.240 para a forma\u00e7\u00e3o de cadastro de reserva, para os cargos de&nbsp;<strong>Escritur\u00e1rio<\/strong>, de n\u00edvel m\u00e9dio de escolaridade, sendo ele dividido em duas \u00e1reas de atua\u00e7\u00e3o:&nbsp;<strong><u>Agente Comercial<\/u><\/strong>&nbsp;e&nbsp;<strong><u>Agente de Tecnologia<\/u><\/strong>. Um quantitativo muito grande, n\u00e3o \u00e9 mesmo?<\/p>\n\n\n\n<p>J\u00e1 para o concurso do<strong>&nbsp;TJ-SP<\/strong>, o cargo ofertado ser\u00e1 o de <strong><span style=\"text-decoration: underline;\">Escrevente T\u00e9cnico Judici\u00e1rio<\/span><\/strong>, n\u00e3o havendo ainda um n\u00famero oficial de quantas vagas ser\u00e3o ofertadas, por\u00e9m, h\u00e1 <strong>6.074 cargos vagos<\/strong> para este cargo, o que aumenta a expectativa de termos um concurso com milhares de vagas, tal como o Banco do Brasil.<\/p>\n\n\n\n<p>Caso a expectativa se cumpra, teremos os dois concursos com milhares de oportunidades, facilitando que haja uma concilia\u00e7\u00e3o no estudo para ambos, uma vez que uma&nbsp;<strong>maior quantidade de vagas oferece uma maior chance de aprova\u00e7\u00e3o.<\/strong><\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-remunera-o-do-banco-do-brasil-e-do-tj-sp\">Remunera\u00e7\u00e3o do Banco do Brasil e do TJ-SP<\/h2>\n\n\n\n<p>A remunera\u00e7\u00e3o do cargo \u00e9 tamb\u00e9m uma vari\u00e1vel importante a ser analisada.<\/p>\n\n\n\n<p>Para o concurso do&nbsp;<strong>Banco do Brasil<\/strong>, a&nbsp;<strong>remunera\u00e7\u00e3o inicial&nbsp;<\/strong>\u00e9 de<strong>&nbsp;R$ 3.022,37<\/strong>,&nbsp;al\u00e9m de diversos&nbsp;<strong>adicionais<\/strong>, como a participa\u00e7\u00e3o nos lucros ou resultados, vale-transporte, aux\u00edlio-creche, ajuda alimenta\u00e7\u00e3o\/refei\u00e7\u00e3o e aux\u00edlio a filho com defici\u00eancia. Nada mal, n\u00e3o \u00e9 mesmo?<\/p>\n\n\n\n<p>Por sua vez, o cargo a ser ofertado para o concurso do&nbsp;<strong>TJ-SP<\/strong>&nbsp;possui uma remunera\u00e7\u00e3o inicial de<strong>&nbsp;R$ 4.981,71<\/strong>, sendo que, com os <strong>adicionais<\/strong>, ele ficar\u00e1 em torno de <strong>R$ 6.000,00<\/strong>.<\/p>\n\n\n\n<p>Diante deste cen\u00e1rio, as remunera\u00e7\u00f5es para ambos os concursos s\u00e3o bastante&nbsp;<strong>atrativas<\/strong>, principalmente considerando que os dois cargos exigem apenas o <strong>ensino m\u00e9dio como escolaridade<\/strong>, ou seja, j\u00e1 \u00e9 poss\u00edvel sair da escola, com apenas 17 anos, e concorrer a um sal\u00e1rio est\u00e1vel de mais de R$ 3.000 ou mais de R$ 5.000, a depender do concurso.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-hist-rico-de-estudo\">Hist\u00f3rico de Estudo<\/h2>\n\n\n\n<p>O hist\u00f3rico de estudos do concurseiro ser\u00e1 um grande diferencial para decidir sobre a possibilidade de conciliar os estudos para os concursos do Banco do Brasil e do TJ-SP.<\/p>\n\n\n\n<p>Estudar para concursos p\u00fablicos nunca foi e nunca ser\u00e1 tarefa f\u00e1cil. Por\u00e9m, cada vez que o estudante realiza uma prova de concurso, vai se criando uma bagagem de estudos, de conhecimento, a qual n\u00e3o \u00e9 perdida, \u00e9 apenas complementada e aprimorada a cada concurso prestado.<\/p>\n\n\n\n<p>Desse modo, os concurseiros que j\u00e1 possuem uma&nbsp;<strong>boa bagagem de provas<\/strong>, com um hist\u00f3rico consider\u00e1vel de concursos j\u00e1 realizados, largam um pouco na frente, inclusive para uma poss\u00edvel concilia\u00e7\u00e3o entre concursos, j\u00e1 que as chances s\u00e3o grandes que algumas disciplinas de cada um deles j\u00e1 tenham sido estudadas em algum momento durante a sua jornada de provas.<\/p>\n\n\n\n<p>Mas e para aqueles que s\u00e3o&nbsp;<strong>marinheiros de primeira viagem?<\/strong>&nbsp;Bom, apesar de ser dif\u00edcil, nada \u00e9 imposs\u00edvel. Como iremos ver no pr\u00f3ximo t\u00f3pico, h\u00e1 disciplinas que ser\u00e3o comuns para ambas as provas. Como o concurso do TJ-SP ainda n\u00e3o est\u00e1 na pra\u00e7a, haver\u00e1 um pouco de tempo, ap\u00f3s a prova do Banco do Brasil, para complementar o estudo das suas disciplinas espec\u00edficas. Desse modo, \u00e9 plenamente poss\u00edvel que haja a concilia\u00e7\u00e3o do estudo das disciplinas comuns para estes concursos, mesmo para o iniciante.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-disciplinas-para-o-banco-do-brasil-e-tj-sp\">Disciplinas para o Banco do Brasil e TJ-SP<\/h2>\n\n\n\n<p>Como j\u00e1 introduzido acima, as disciplinas para os dois concursos s\u00e3o decisivas para que haja uma concilia\u00e7\u00e3o efetiva de estudo para os certames do Banco do Brasil e do TJ-SP.<\/p>\n\n\n\n<p>Para o concurso do&nbsp;<strong>Banco do Brasil<\/strong>, iremos analisar as disciplinas para o cargo de&nbsp;<strong>Agente Comercial<\/strong>, presentes no <strong>edital rec\u00e9m-publicado<\/strong>. J\u00e1 para o concurso do&nbsp;<strong>TJ-SP<\/strong>, a an\u00e1lise ser\u00e1 realizada para o cargo que ser\u00e1 ofertado, em rela\u00e7\u00e3o ao <strong>\u00faltimo concurso realizado<\/strong>, em 2018. Iremos realizar o nosso estudo desta maneira j\u00e1 que ambos os cargos possuem a escolaridade de&nbsp;<strong>n\u00edvel m\u00e9dio<\/strong>, al\u00e9m da probabilidade de eles serem os&nbsp;<strong>mais requisitados<\/strong>&nbsp;pelos candidatos.<\/p>\n\n\n\n<p>As disciplinas presentes nos editais para os cargos acima podem ser vistas abaixo:<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"567\" height=\"303\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/07\/04111450\/image-128.png\" alt=\"Disciplinas para o Banco do Brasil e TJ-SP\" class=\"wp-image-786236\" srcset=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/07\/04111450\/image-128.png 567w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/07\/04111450\/image-128-300x160.png 300w\" sizes=\"auto, (max-width: 567px) 100vw, 567px\" \/><figcaption>Disciplinas para o Banco do Brasil e TJ-SP<\/figcaption><\/figure><\/div>\n\n\n\n<p>O conte\u00fado program\u00e1tico presente no edital do&nbsp;<strong>Banco do Brasil<\/strong>&nbsp;para o cargo de Agente Comercial engloba&nbsp;<strong>9 disciplinas.<\/strong><\/p>\n\n\n\n<p>Ele \u00e9 mais voltado para assuntos da \u00e1rea banc\u00e1ria, por\u00e9m, h\u00e1 algumas disciplinas que est\u00e3o sempre presentes em quase todos os concursos, de diversas \u00e1reas, como&nbsp;<strong>Portugu\u00eas, Inform\u00e1tica, Matem\u00e1tica B\u00e1sica e Racioc\u00ednio L\u00f3gico e Matem\u00e1tica Financeira.<\/strong><\/p>\n\n\n\n<p>J\u00e1 o \u00faltimo edital, de 2018, para o cargo de escrevente do <strong>TJ-SP,&nbsp;<\/strong>o qual possui grandes chances de ser similar ao pr\u00f3ximo que ser\u00e1 publicado, trouxe<strong>&nbsp;12 disciplinas.<\/strong><\/p>\n\n\n\n<p>Al\u00e9m das disciplinas b\u00e1sicas similares \u00e0s do Banco do Brasil, ele traz um enfoque em algumas disciplinas do Direito, como Administrativo, Constitucional e Penal.<\/p>\n\n\n\n<p>Perceba que h\u00e1 uma boa quantidade de&nbsp;<strong>disciplinas similares&nbsp;<\/strong>em ambos os concursos, o que facilita uma poss\u00edvel concilia\u00e7\u00e3o dos estudos para ambas as provas.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-aulas-do-estrat-gia-para-o-banco-do-brasil-e-tj-sp\">Aulas do Estrat\u00e9gia para o Banco do Brasil e TJ-SP<\/h2>\n\n\n\n<p>Agora vamos a um ponto muito importante. Voc\u00ea j\u00e1 deve saber que o<strong>&nbsp;<span class=\"has-inline-color has-vivid-cyan-blue-color\">Estrat\u00e9gia Concursos \u00e9 a empresa que mais aprova em concursos p\u00fablicos.<\/span><\/strong><\/p>\n\n\n\n<p>N\u00f3s j\u00e1 temos disponibilizadas<strong>&nbsp;dezenas de videoaulas e PDFs para os concursos do Banco do Brasil e do TJ-SP.<\/strong>&nbsp;Desse modo, muitas dessas aulas, ao serem estudadas, poder\u00e3o ser aproveitadas para as duas provas. Por exemplo, ao assistir \u00e0s aulas de Portugu\u00eas para o concurso do TJ-SP, voc\u00ea j\u00e1 estar\u00e1, automaticamente, estudando para esta disciplina para o concurso do Banco do Brasil.<\/p>\n\n\n\n<p>Desse modo, realizamos uma&nbsp;<strong>compara\u00e7\u00e3o&nbsp;<\/strong>entre os dois concursos, com o intuito de conferir quantas&nbsp;<strong>aulas&nbsp;<\/strong>presentes nos&nbsp;<strong>cursos do Estrat\u00e9gia Concursos<\/strong>&nbsp;podem ser&nbsp;<strong>aproveitadas&nbsp;<\/strong>para os&nbsp;<strong>dois certames,&nbsp;<\/strong>e quantas ser\u00e3o exclusivas para cada um.<\/p>\n\n\n\n<p>Primeiramente, vamos mostrar abaixo&nbsp;<strong>quantas aulas<\/strong>, presentes nos cursos do Estrat\u00e9gia,&nbsp;<strong>h\u00e1 em cada disciplina<\/strong>&nbsp;para os dois concursos:<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"702\" height=\"335\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/07\/04115758\/image-136.png\" alt=\"Aulas do Estrat\u00e9gia para o Banco do Brasil e TJ-SP\" class=\"wp-image-786258\" srcset=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/07\/04115758\/image-136.png 702w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/07\/04115758\/image-136-300x143.png 300w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/07\/04115758\/image-136-610x291.png 610w\" sizes=\"auto, (max-width: 702px) 100vw, 702px\" \/><figcaption>Aulas do Estrat\u00e9gia para o Banco do Brasil e TJ-SP<\/figcaption><\/figure><\/div>\n\n\n\n<p>Na tabela acima, vemos a&nbsp;quantidade de aulas&nbsp;de cada mat\u00e9ria para os dois concursos. Percebe-se que h\u00e1 algumas disciplinas diferentes, mas tamb\u00e9m h\u00e1 aquelas que podem ser&nbsp;<strong>aproveitadas para os dois certames,&nbsp;<\/strong>como&nbsp;<strong>Portugu\u00eas, Matem\u00e1tica e Racioc\u00ednio L\u00f3gico, Inform\u00e1tica, Matem\u00e1tica Financeira e o Estatuto da Pessoa com Defici\u00eancia.<\/strong><\/p>\n\n\n\n<p>Vamos agora tomar como&nbsp;<strong>refer\u00eancia&nbsp;<\/strong>o concurso do&nbsp;<strong>TJ-SP.<\/strong>&nbsp;Assim, caso voc\u00ea j\u00e1 tenha<strong>&nbsp;estudado todas as aulas&nbsp;<\/strong>do&nbsp;<strong>Estrat\u00e9gia&nbsp;<\/strong>para o concurso do&nbsp;<strong>TJ-SP<\/strong>, quantas delas poder\u00e3o ser&nbsp;<strong>aproveitadas<\/strong>,&nbsp;<strong>automaticamente<\/strong>, para o concurso do&nbsp;<strong>Banco do Brasil?<\/strong>&nbsp;A resposta voc\u00ea pode conferir na tabela abaixo:<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"138\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/07\/04111420\/image-124-1024x138.png\" alt=\"Aulas\" class=\"wp-image-786232\" srcset=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/07\/04111420\/image-124-1024x138.png 1024w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/07\/04111420\/image-124-300x40.png 300w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/07\/04111420\/image-124-768x104.png 768w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/07\/04111420\/image-124-610x82.png 610w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/07\/04111420\/image-124.png 1193w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption>Aulas TJ-SP x Aulas Banco do Brasil<\/figcaption><\/figure>\n\n\n\n<p>N\u00e3o entendeu nada da tabela acima? Venha comigo, pois irei explicar.<\/p>\n\n\n\n<p>Em rela\u00e7\u00e3o \u00e0 disciplina de&nbsp;<strong><u>Portugu\u00eas<\/u><\/strong>, vemos que a&nbsp;<strong>aula 0 de Portugu\u00eas do Banco do Brasil n\u00e3o possui correspond\u00eancia com nenhuma aula do TJ-SP, j\u00e1 que possui um \u201ctra\u00e7o\u201d. Por\u00e9m, a aula 1 do BB corresponde \u00e0 aula 0 do TJ-SP; <\/strong>a aula 2 do BB corresponde \u00e0 aula 1 do TJ-SP, e assim por diante. Analisando a tabela ainda, percebemos que, para esta mat\u00e9ria, h\u00e1 a <strong>correspond\u00eancia de 80% entre elas<\/strong>. Ou seja,&nbsp;caso voc\u00ea j\u00e1 tenha estudado todas as aulas de portugu\u00eas para o TJ-SP presentes no pacote do Estrat\u00e9gia, voc\u00ea j\u00e1 ter\u00e1 estudado 80% de todo o conte\u00fado desta disciplina para o concurso do Banco do Brasil.<\/p>\n\n\n\n<p>Em&nbsp;<strong><u>Matem\u00e1tica<\/u><\/strong>, h\u00e1&nbsp;<strong>18 aulas<\/strong>&nbsp;tanto para o&nbsp;<strong>Banco do Brasil&nbsp;quanto para o TJ-SP <\/strong>de Matem\u00e1tica, por\u00e9m, nem todas s\u00e3o iguais, como mostra a tabela. Percebe-se que as&nbsp;<strong>aulas 0 e 1<\/strong>&nbsp;s\u00e3o as&nbsp;<strong>mesmas&nbsp;<\/strong>para os dois concursos, havendo tamb\u00e9m a correspond\u00eancia das aulas 2 e 3, mas em posi\u00e7\u00f5es trocadas no curso. Entretanto, h\u00e1 v\u00e1rias aulas com&nbsp;<strong>\u201ctra\u00e7o\u201d<\/strong>, o qual significa que aquela aula do Banco do Brasil&nbsp;<strong>n\u00e3o possui correspond\u00eancia<\/strong>&nbsp;com as aulas do TJ-SP. Assim, ao estudar para o TJ-SP, voc\u00ea j\u00e1 ter\u00e1 estudado&nbsp;<strong>44,44%<\/strong>&nbsp;do conte\u00fado de Matem\u00e1tica para o Banco do Brasil.<\/p>\n\n\n\n<p>De maneira similar, temos&nbsp;<strong>9 aulas<\/strong>&nbsp;de&nbsp;<strong><u>Inform\u00e1tica<\/u><\/strong>&nbsp;para o&nbsp;<strong>TJ-SP&nbsp;<\/strong>e&nbsp;<strong>19&nbsp;<\/strong>para o&nbsp;<strong>Banco do Brasil<\/strong>. Dessas 19 aulas do Banco do Brasil,&nbsp;<strong>9 possuem correspond\u00eancia<\/strong>&nbsp;com aulas do TJ-SP, como podemos ver na tabela acima. Desse modo, caso voc\u00ea j\u00e1 tenha estudado todas as 9 aulas de inform\u00e1tica para o TJ-SP, voc\u00ea j\u00e1 ter\u00e1 estudado, automaticamente, 9 aulas para o concurso do Banco do Brasil, ou seja,&nbsp;<strong>47,37%<\/strong>&nbsp;do conte\u00fado de Inform\u00e1tica do BB, restando apenas mais 8 aulas para serem estudadas.<\/p>\n\n\n\n<p>J\u00e1 em <strong><span style=\"text-decoration: underline;\">Matem\u00e1tica Financeira<\/span><\/strong>, h\u00e1 apenas 1 aula para o concurso do TJ-SP, sendo que ela pode ser aproveitada para o concurso do BB. Desse modo, outras 5 dever\u00e3o ser estudadas. Assim, h\u00e1 a correspond\u00eancia de <strong>16,67%<\/strong> entre os dois concursos.<\/p>\n\n\n\n<p>Por fim, o <strong><span style=\"text-decoration: underline;\">Estatuto da Pessoa com Defici\u00eancia<\/span><\/strong> \u00e9 cobrado nos dois concursos, sendo que <strong>todas as aulas podem ser aproveitadas para os dois concursos<\/strong>, havendo uma correspond\u00eancia de <strong>100%<\/strong> entre elas. Assim, ao estudar para o concurso do TJ-SP, toda a mat\u00e9ria desta disciplina j\u00e1 estar\u00e1 estudada para o concurso do Banco do Brasil.<\/p>\n\n\n\n<p>Vamos visualizar a similaridade destas disciplinas em um gr\u00e1fico?<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"591\" height=\"339\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/07\/04112150\/image-131.png\" alt=\"Similaridade\" class=\"wp-image-786239\" srcset=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/07\/04112150\/image-131.png 591w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/07\/04112150\/image-131-300x172.png 300w\" sizes=\"auto, (max-width: 591px) 100vw, 591px\" \/><figcaption>Similaridade para conciliar TJ-SP e Banco do Brasil<\/figcaption><\/figure><\/div>\n\n\n\n<p>De uma maneira geral, <strong>das 101 aulas para o Banco do Brasil<\/strong>, englobando todas as disciplinas, <strong>29 j\u00e1 foram estudadas<\/strong>, caso o concurseiro j\u00e1 tenha estudado todas as aulas para o TJ-SP.<\/p>\n\n\n\n<p>Assim, restaria ainda mais da metade do conte\u00fado do Banco do Brasil para ser estudado, para aqueles que j\u00e1 estudaram as disciplinas do TJ-SP. Por\u00e9m, com essa grande quantidade de similaridade entre os seus conte\u00fados, n\u00e3o fica t\u00e3o dif\u00edcil concili\u00e1-los, n\u00e3o \u00e9 mesmo?<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-finalizando\">Finalizando<\/h2>\n\n\n\n<p>Bom, pessoal! H\u00e1&nbsp;<strong>diversas vari\u00e1veis<\/strong>&nbsp;a serem analisadas para concluir qual concurso&nbsp;<strong>focar&nbsp;<\/strong>ou se ser\u00e1 poss\u00edvel&nbsp;<strong>conciliar&nbsp;<\/strong>o estudo para os dois certames. Procuramos expor algumas informa\u00e7\u00f5es importantes sobre a possibilidade de concilia\u00e7\u00e3o dos dois concursos.<\/p>\n\n\n\n<p>Para aqueles que j\u00e1 estavam estudando para o concurso do TJ-SP, \u00e9 poss\u00edvel uma <strong>migra\u00e7\u00e3o <\/strong>tempor\u00e1ria para o concurso do Banco do Brasil, enquanto o seu edital n\u00e3o \u00e9 publicado. Por\u00e9m, isto \u00e9 uma decis\u00e3o individual de cada concurseiro.<\/p>\n\n\n\n<p>Seja qual for a sua op\u00e7\u00e3o, voc\u00ea poder\u00e1 encontrar, no site do&nbsp;<strong>Estrat\u00e9gia Concursos<\/strong>, cursos para o<strong>&nbsp;<a href=\"https:\/\/www.estrategiaconcursos.com.br\/cursosPorConcurso\/banco-do-brasil-escriturario-99\/\" target=\"_blank\" rel=\"noreferrer noopener\">Banco do Brasil<\/a>&nbsp;e para o <a href=\"https:\/\/www.estrategiaconcursos.com.br\/curso\/1-pacote-completo-p-tj-sp-escrevente-judiciario-2021-pre-edital\/\" target=\"_blank\" rel=\"noreferrer noopener\">TJ-SP<\/a><\/strong>. L\u00e1, voc\u00ea encontrar\u00e1&nbsp;<strong>aulas completas e detalhadas, com os melhores professores do mercado.<\/strong><\/p>\n\n\n\n<p>Conhe\u00e7a tamb\u00e9m o&nbsp;<a href=\"https:\/\/questoes.estrategiaconcursos.com.br\/\" target=\"_blank\" rel=\"noreferrer noopener\">Sistema de Quest\u00f5es do Estrat\u00e9gia<\/a>. Afinal, a \u00fanica maneira de&nbsp;<strong>consolidar o conte\u00fado&nbsp;<\/strong>de maneira satisfat\u00f3ria \u00e9 atrav\u00e9s da&nbsp;<strong>resolu\u00e7\u00e3o de quest\u00f5es.<\/strong><\/p>\n\n\n\n<p>Bons estudos e at\u00e9 a pr\u00f3xima!<\/p>\n\n\n\n<h2 class=\"has-text-align-center wp-block-heading\" id=\"h-cursos-e-assinaturas\">Cursos e Assinaturas<\/h2>\n\n\n\n<p>Prepare-se com o melhor material e com quem mais aprova em Concursos P\u00fablicos em todo o pa\u00eds!<\/p>\n\n\n\n<div class=\"container\" id=\"boxes\">\n  <div class=\"row\">\n    <div class=\"col-sm\">\n      <div class=\"estrategia\" id=\"box-assinatura\">\n        <h3 class=\"titulo-assinatura\">Assinatura de Concursos<\/h3>\n        <p class=\"subtitulo-assinatura\">Assinatura de 1 ano ou 2 anos<\/p>\n        <div class=\"box-botao\">\n          <a class=\"btn-assinatura\" target=\"_blank\" href=\"https:\/\/www.estrategiaconcursos.com.br\/assinaturas\/\" role=\"button\" rel=\"noopener noreferrer\">ASSINE AGORA<\/a>\n        <\/div>\n      <\/div>\n      <p class=\"texto-auxiliar\"><\/p>\n    <\/div>\n    <div class=\"col-sm\">\n      <div class=\"questoes\" id=\"box-assinatura\">\n        <h3 class=\"titulo-assinatura\">Sistema de Quest\u00f5es<\/h3>\n        <p class=\"subtitulo-assinatura\">Assinatura de 1 ano ou 2 anos\n<\/p>\n        <div class=\"box-botao\">\n          <a class=\"btn-assinatura\" target=\"_blank\" href=\"https:\/\/www.estrategiaconcursos.com.br\/cursosPorConcurso\/sistema-de-questoes\/#\/\" role=\"button\" rel=\"noopener noreferrer\">ASSINE AGORA<\/a>\n        <\/div>\n      <\/div>\n      <p class=\"texto-auxiliar\"><\/p>\n    <\/div>\n  <\/div>\n<\/div>\n\n\n\n<div class=\"container\" id=\"boxes\">\n  <div class=\"row\">\n\n    <div class=\"col-sm\" id=\"boxes-concursos\">\n      <div style=\"background-color: #005DAD;\" class=\"conteudo-concursos\" id=\"box-concursos\">\n        <h3 class=\"titulo-assinatura\">Concursos Abertos<\/h3>\n        <p class=\"subtitulo-assinatura\">mais de 15 mil vagas<\/p>\n        <div class=\"box-botao\">\n          <a class=\"btn-assinatura\" target=\"_blank\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-abertos\/\" role=\"button\" rel=\"noopener noreferrer\">Conhe\u00e7a Agora<\/a>\n        <\/div>\n      <\/div>\n    <\/div>\n\n    \n\n    <div class=\"col-sm\" id=\"boxes-concursos\">\n      <div style=\"background-color: #419FF0;\" class=\"conteudo-concursos\" id=\"box-concursos\">\n        <h3 class=\"titulo-assinatura\">Concursos 2021<\/h3>\n        <p class=\"subtitulo-assinatura\">mais de 17 mil vagas<\/p>\n        <div class=\"box-botao\">\n          <a class=\"btn-assinatura\" target=\"_blank\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-2021\/\" role=\"button\" rel=\"noopener noreferrer\">Conhe\u00e7a Agora<\/a>\n        <\/div>\n      <\/div>\n    <\/div>\n\n  <\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Veja neste artigo sobre as possibilidades de conciliar os estudos para os concursos do&nbsp;Banco do Brasil&nbsp;e do TJ-SP. Ol\u00e1, pessoal! Tudo bem com voc\u00eas? O segundo semestre de 2021 est\u00e1 com tudo na \u00e1rea dos concursos.&nbsp;Dezenas de provas que ficaram represadas durante mais de um ano de pandemia est\u00e3o saindo agora, quase que simultaneamente, al\u00e9m [&hellip;]<\/p>\n","protected":false},"author":1976,"featured_media":786244,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"post_tipo":"article","footnotes":""},"categories":[2313,1,1984],"tags":[],"tax_estado":[219964,219965,219966,219967,219968,219969,219963,219970,219971,219972,219973,219974,219975,219976,219977,219978,219979,219980,219981,219982,219983,219984,219985,219986,219987,219988,219989,219990],"class_list":["post-786228","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-carreiras-bancarias","category-cursos-e-concursos","category-tribunais","tax_estado-ac","tax_estado-al","tax_estado-am","tax_estado-ap","tax_estado-ba","tax_estado-ce","tax_estado-concursos-federais","tax_estado-df","tax_estado-es","tax_estado-go","tax_estado-ma","tax_estado-mg","tax_estado-ms","tax_estado-mt","tax_estado-pa","tax_estado-pb","tax_estado-pe","tax_estado-pi","tax_estado-pr","tax_estado-rj","tax_estado-rn","tax_estado-ro","tax_estado-rr","tax_estado-rs","tax_estado-sc","tax_estado-se","tax_estado-sp","tax_estado-to"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.2 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Banco do Brasil e TJ-SP: \u00c9 poss\u00edvel conciliar os estudos?<\/title>\n<meta name=\"description\" content=\"Confira neste artigo uma an\u00e1lise sobre as possibilidades de conciliar os estudos para os concursos do Banco do Brasil e do TJ-SP.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/conciliar-banco-do-brasil-tj-sp\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Banco do Brasil e TJ-SP: \u00c9 poss\u00edvel conciliar os estudos?\" \/>\n<meta property=\"og:description\" content=\"Confira neste artigo uma an\u00e1lise sobre as possibilidades de conciliar os estudos para os concursos do Banco do Brasil e do TJ-SP.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/conciliar-banco-do-brasil-tj-sp\/\" \/>\n<meta property=\"og:site_name\" content=\"Estrat\u00e9gia Concursos\" \/>\n<meta property=\"article:published_time\" content=\"2021-07-07T16:59:37+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-07-07T17:00:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/07\/04113256\/tj-sp-e-bb.png\" \/>\n\t<meta property=\"og:image:width\" content=\"367\" \/>\n\t<meta property=\"og:image:height\" content=\"293\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Kassio Henrique Sobral Rocha\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:site\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Kassio Henrique Sobral Rocha\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"11 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/conciliar-banco-do-brasil-tj-sp\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/conciliar-banco-do-brasil-tj-sp\/\"},\"author\":{\"name\":\"Kassio Henrique Sobral Rocha\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/f0c830e07cfe11c231c0ea5dbb036df5\"},\"headline\":\"Banco do Brasil e TJ-SP: \u00c9 poss\u00edvel conciliar os estudos?\",\"datePublished\":\"2021-07-07T16:59:37+00:00\",\"dateModified\":\"2021-07-07T17:00:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/conciliar-banco-do-brasil-tj-sp\/\"},\"wordCount\":2321,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/conciliar-banco-do-brasil-tj-sp\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/07\/04113256\/tj-sp-e-bb.png\",\"articleSection\":[\"Banc\u00e1ria (BB, CEF e Bancos Estaduais)\",\"Concursos P\u00fablicos\",\"Tribunais\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/conciliar-banco-do-brasil-tj-sp\/#respond\"]}],\"copyrightYear\":\"2021\",\"copyrightHolder\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/conciliar-banco-do-brasil-tj-sp\/\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/conciliar-banco-do-brasil-tj-sp\/\",\"name\":\"Banco do Brasil e TJ-SP: \u00c9 poss\u00edvel conciliar os estudos?\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/conciliar-banco-do-brasil-tj-sp\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/conciliar-banco-do-brasil-tj-sp\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/07\/04113256\/tj-sp-e-bb.png\",\"datePublished\":\"2021-07-07T16:59:37+00:00\",\"dateModified\":\"2021-07-07T17:00:11+00:00\",\"description\":\"Confira neste artigo uma an\u00e1lise sobre as possibilidades de conciliar os estudos para os concursos do Banco do Brasil e do TJ-SP.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/conciliar-banco-do-brasil-tj-sp\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/conciliar-banco-do-brasil-tj-sp\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/conciliar-banco-do-brasil-tj-sp\/#primaryimage\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/07\/04113256\/tj-sp-e-bb.png\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/07\/04113256\/tj-sp-e-bb.png\",\"width\":367,\"height\":293,\"caption\":\"conciliar tj-sp e bb\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/conciliar-banco-do-brasil-tj-sp\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Banco do Brasil e TJ-SP: \u00c9 poss\u00edvel conciliar os estudos?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"name\":\"Estrat\u00e9gia Concursos\",\"description\":\"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.\",\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\",\"name\":\"Estrat\u00e9gia Concursos\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"width\":230,\"height\":60,\"caption\":\"Estrat\u00e9gia Concursos\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/EstratConcursos\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/f0c830e07cfe11c231c0ea5dbb036df5\",\"name\":\"Kassio Henrique Sobral Rocha\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/d10350cbdad043facd8ec77a377f86f9026afee3348e463b04854fd4490ce759?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/d10350cbdad043facd8ec77a377f86f9026afee3348e463b04854fd4490ce759?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/d10350cbdad043facd8ec77a377f86f9026afee3348e463b04854fd4490ce759?s=96&d=mm&r=g\",\"caption\":\"Kassio Henrique Sobral Rocha\"},\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/kassio-rochayahoo-com-br\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Banco do Brasil e TJ-SP: \u00c9 poss\u00edvel conciliar os estudos?","description":"Confira neste artigo uma an\u00e1lise sobre as possibilidades de conciliar os estudos para os concursos do Banco do Brasil e do TJ-SP.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.estrategiaconcursos.com.br\/blog\/conciliar-banco-do-brasil-tj-sp\/","og_locale":"pt_BR","og_type":"article","og_title":"Banco do Brasil e TJ-SP: \u00c9 poss\u00edvel conciliar os estudos?","og_description":"Confira neste artigo uma an\u00e1lise sobre as possibilidades de conciliar os estudos para os concursos do Banco do Brasil e do TJ-SP.","og_url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/conciliar-banco-do-brasil-tj-sp\/","og_site_name":"Estrat\u00e9gia Concursos","article_published_time":"2021-07-07T16:59:37+00:00","article_modified_time":"2021-07-07T17:00:11+00:00","og_image":[{"width":367,"height":293,"url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/07\/04113256\/tj-sp-e-bb.png","type":"image\/png"}],"author":"Kassio Henrique Sobral Rocha","twitter_card":"summary_large_image","twitter_creator":"@EstratConcursos","twitter_site":"@EstratConcursos","twitter_misc":{"Escrito por":"Kassio Henrique Sobral Rocha","Est. tempo de leitura":"11 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/conciliar-banco-do-brasil-tj-sp\/#article","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/conciliar-banco-do-brasil-tj-sp\/"},"author":{"name":"Kassio Henrique Sobral Rocha","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/f0c830e07cfe11c231c0ea5dbb036df5"},"headline":"Banco do Brasil e TJ-SP: \u00c9 poss\u00edvel conciliar os estudos?","datePublished":"2021-07-07T16:59:37+00:00","dateModified":"2021-07-07T17:00:11+00:00","mainEntityOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/conciliar-banco-do-brasil-tj-sp\/"},"wordCount":2321,"commentCount":0,"publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/conciliar-banco-do-brasil-tj-sp\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/07\/04113256\/tj-sp-e-bb.png","articleSection":["Banc\u00e1ria (BB, CEF e Bancos Estaduais)","Concursos P\u00fablicos","Tribunais"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/conciliar-banco-do-brasil-tj-sp\/#respond"]}],"copyrightYear":"2021","copyrightHolder":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/conciliar-banco-do-brasil-tj-sp\/","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/conciliar-banco-do-brasil-tj-sp\/","name":"Banco do Brasil e TJ-SP: \u00c9 poss\u00edvel conciliar os estudos?","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/conciliar-banco-do-brasil-tj-sp\/#primaryimage"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/conciliar-banco-do-brasil-tj-sp\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/07\/04113256\/tj-sp-e-bb.png","datePublished":"2021-07-07T16:59:37+00:00","dateModified":"2021-07-07T17:00:11+00:00","description":"Confira neste artigo uma an\u00e1lise sobre as possibilidades de conciliar os estudos para os concursos do Banco do Brasil e do TJ-SP.","breadcrumb":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/conciliar-banco-do-brasil-tj-sp\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/conciliar-banco-do-brasil-tj-sp\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/conciliar-banco-do-brasil-tj-sp\/#primaryimage","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/07\/04113256\/tj-sp-e-bb.png","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/07\/04113256\/tj-sp-e-bb.png","width":367,"height":293,"caption":"conciliar tj-sp e bb"},{"@type":"BreadcrumbList","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/conciliar-banco-do-brasil-tj-sp\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.estrategiaconcursos.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Banco do Brasil e TJ-SP: \u00c9 poss\u00edvel conciliar os estudos?"}]},{"@type":"WebSite","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","name":"Estrat\u00e9gia Concursos","description":"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.","publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization","name":"Estrat\u00e9gia Concursos","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","width":230,"height":60,"caption":"Estrat\u00e9gia Concursos"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/EstratConcursos"]},{"@type":"Person","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/f0c830e07cfe11c231c0ea5dbb036df5","name":"Kassio Henrique Sobral Rocha","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/d10350cbdad043facd8ec77a377f86f9026afee3348e463b04854fd4490ce759?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/d10350cbdad043facd8ec77a377f86f9026afee3348e463b04854fd4490ce759?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d10350cbdad043facd8ec77a377f86f9026afee3348e463b04854fd4490ce759?s=96&d=mm&r=g","caption":"Kassio Henrique Sobral Rocha"},"url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/kassio-rochayahoo-com-br\/"}]}},"_links":{"self":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/786228","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/users\/1976"}],"replies":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/comments?post=786228"}],"version-history":[{"count":14,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/786228\/revisions"}],"predecessor-version":[{"id":789393,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/786228\/revisions\/789393"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media\/786244"}],"wp:attachment":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media?parent=786228"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/categories?post=786228"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tags?post=786228"},{"taxonomy":"tax_estado","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tax_estado?post=786228"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}