{"id":778374,"date":"2021-06-27T20:54:25","date_gmt":"2021-06-27T23:54:25","guid":{"rendered":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?p=778374"},"modified":"2021-06-27T20:54:27","modified_gmt":"2021-06-27T23:54:27","slug":"gabarito-depen-direito-penal-extraoficial","status":"publish","type":"post","link":"https:\/\/www.estrategiaconcursos.com.br\/blog\/gabarito-depen-direito-penal-extraoficial\/","title":{"rendered":"GABARITO DEPEN &#8211; Direito Penal (extraoficial)"},"content":{"rendered":"\n<p class=\"has-text-align-center\">GABARITO DEPEN &#8211; Direito Penal<\/p>\n\n\n\n<p>Ol\u00e1, pessoal<\/p>\n\n\n\n<p>Para quem n\u00e3o me conhece ainda, meu nome \u00e9 <strong>Renan Araujo<\/strong> e sou professor aqui no Estrat\u00e9gia Concursos, lecionando as mat\u00e9rias de Direito Penal e Processual Penal.<\/p>\n\n\n\n<p>Antes de prosseguir, <strong>convido voc\u00ea a me seguir no INSTAGRAM<\/strong>:<strong>&nbsp;<a href=\"http:\/\/www.instagram.com\/profrenanaraujo\/?hl=pt-br\">Instagram do Prof. Renan Araujo<\/a><\/strong><\/p>\n\n\n\n<p>Neste artigo vamos comentar as quest\u00f5es de <strong>Direito Penal <\/strong>que foram cobradas pela Banca <strong>CESPE<\/strong> no concurso do <strong>DEPEN<\/strong>, cuja prova foi realizada hoje, 27.06.2021.<\/p>\n\n\n\n<p>A prova teve um n\u00edvel tranquilo, e quem estudou pelo nosso material certamente se saiu bem!<\/p>\n\n\n\n<p>Vamos aos coment\u00e1rios:<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"434\" height=\"245\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/06\/27205238\/image-542.png\" alt=\"\" class=\"wp-image-778377\" srcset=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/06\/27205238\/image-542.png 434w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/06\/27205238\/image-542-300x169.png 300w\" sizes=\"auto, (max-width: 434px) 100vw, 434px\" \/><\/figure>\n\n\n\n<p><strong>45. (CESPE\/2021\/DEPEN)<\/strong><\/p>\n\n\n\n<p><strong>COMENT\u00c1RIOS<\/strong><\/p>\n\n\n\n<p>Item errado, pois o crime de extors\u00e3o admite tentativa, na medida em que \u00e9 perfeitamente poss\u00edvel o agente iniciar a execu\u00e7\u00e3o do delito e a consuma\u00e7\u00e3o n\u00e3o ocorrer por circunst\u00e2ncias alheias \u00e0 vontade do agente (ex.: Jos\u00e9 manda uma carta extorquindo Maria, mas a carta \u00e9 interceptada pela pol\u00edcia).<\/p>\n\n\n\n<p>O fato de ser crime formal n\u00e3o impede a configura\u00e7\u00e3o da tentativa.<\/p>\n\n\n\n<p><strong>GABARITO: ERRADA<\/strong><\/p>\n\n\n\n<p><strong>46. (CESPE\/2021\/DEPEN)<\/strong><\/p>\n\n\n\n<p><strong>COMENT\u00c1RIOS<\/strong><\/p>\n\n\n\n<p>Item errado, pois nesse caso haver\u00e1 leg\u00edtima defesa, nos termos do art. 25, \u00a7 \u00fanico do CP:<\/p>\n\n\n\n<p><em>Art. 25 (&#8230;) Par\u00e1grafo \u00fanico. Observados os requisitos previstos no caput deste artigo, considera-se tamb\u00e9m em leg\u00edtima defesa o agente de seguran\u00e7a p\u00fablica que repele agress\u00e3o ou risco de agress\u00e3o a v\u00edtima mantida ref\u00e9m durante a pr\u00e1tica de crimes.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; (Inclu\u00eddo pela Lei n\u00ba 13.964, de 2019)&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; (Vide ADPF 779)<\/em><\/p>\n\n\n\n<p><strong>GABARITO: ERRADA<\/strong><\/p>\n\n\n\n<p><strong>47. (CESPE\/2021\/DEPEN)<\/strong><\/p>\n\n\n\n<p><strong>COMENT\u00c1RIOS<\/strong><\/p>\n\n\n\n<p>Item correto, pois na falsidade ideol\u00f3gica n\u00e3o h\u00e1 elementos estruturantes falsificados a serem apurados em per\u00edcia. A forma do documento \u00e9 verdadeira, sendo falso apenas o conte\u00fado, a informa\u00e7\u00e3o ali contida, n\u00e3o havendo adultera\u00e7\u00e3o, rasura ou qualquer outra falsifica\u00e7\u00e3o material.<\/p>\n\n\n\n<p><strong>GABARITO: CORRETA<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"438\" height=\"152\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/06\/27205247\/image-543.png\" alt=\"\" class=\"wp-image-778378\" srcset=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/06\/27205247\/image-543.png 438w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/06\/27205247\/image-543-300x104.png 300w\" sizes=\"auto, (max-width: 438px) 100vw, 438px\" \/><\/figure>\n\n\n\n<p><strong>48. (CESPE\/2021\/DEPEN)<\/strong><\/p>\n\n\n\n<p><strong>COMENT\u00c1RIOS<\/strong><\/p>\n\n\n\n<p>Item errado, pois a nova lei abolitiva se aplica aos fatos pret\u00e9ritos, ainda que j\u00e1 decididos por senten\u00e7a penal condenat\u00f3ria transitada em julgado, fazendo cessar a pena e os efeitos PENAIS da condena\u00e7\u00e3o, mas n\u00e3o afeta os efeitos extrapenais, na forma do art. 2\u00ba do CP:<\/p>\n\n\n\n<p><em>Art. 2\u00ba &#8211; Ningu\u00e9m pode ser punido por fato que lei posterior deixa de considerar crime, cessando em virtude dela a execu\u00e7\u00e3o e os efeitos penais da senten\u00e7a condenat\u00f3ria.&nbsp; (Reda\u00e7\u00e3o dada pela Lei n\u00ba 7.209, de 11.7.1984)<\/em><\/p>\n\n\n\n<p><strong>GABARITO: ERRADA<\/strong><\/p>\n\n\n\n<p><strong>49. (CESPE\/2021\/DEPEN)<\/strong><\/p>\n\n\n\n<p><strong>COMENT\u00c1RIOS<\/strong><\/p>\n\n\n\n<p>Item errado, pois a interpreta\u00e7\u00e3o anal\u00f3gica \u00e9 perfeitamente admitida, seja ela ben\u00e9fica ou prejudicial ao agente. A analogia (que n\u00e3o se confunde com interpreta\u00e7\u00e3o anal\u00f3gica) \u00e9 que possui restri\u00e7\u00e3o, s\u00f3 sendo admitida quando ben\u00e9fica ao agente.<\/p>\n\n\n\n<p><strong>GABARITO: ERRADA<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"446\" height=\"399\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/06\/27205303\/image-544.png\" alt=\"\" class=\"wp-image-778379\" srcset=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/06\/27205303\/image-544.png 446w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/06\/27205303\/image-544-300x268.png 300w\" sizes=\"auto, (max-width: 446px) 100vw, 446px\" \/><\/figure>\n\n\n\n<p><strong>50. (CESPE\/2021\/DEPEN)<\/strong><\/p>\n\n\n\n<p><strong>COMENT\u00c1RIOS<\/strong><\/p>\n\n\n\n<p>Item correto, pois o agente desacatou funcion\u00e1rio p\u00fablico EM RAZ\u00c3O DA FUN\u00c7\u00c3O. Mesmo a v\u00edtima n\u00e3o estando em servi\u00e7o no momento das ofensas, o fato se deu em raz\u00e3o da fun\u00e7\u00e3o, motivo pelo qual h\u00e1 desacato, crime previsto no art. 331 do CP:<\/p>\n\n\n\n<p><em>Art. 331 &#8211; Desacatar funcion\u00e1rio p\u00fablico no exerc\u00edcio da fun\u00e7\u00e3o ou em raz\u00e3o dela:<\/em><\/p>\n\n\n\n<p><em>Pena &#8211; deten\u00e7\u00e3o, de seis meses a dois anos, ou multa.<\/em><\/p>\n\n\n\n<p><strong>GABARITO: CORRETA<\/strong><\/p>\n\n\n\n<p><strong>51. (CESPE\/2021\/DEPEN)<\/strong><\/p>\n\n\n\n<p><strong>COMENT\u00c1RIOS<\/strong><\/p>\n\n\n\n<p>Item errado, pois nesse caso n\u00e3o h\u00e1 que se falar em subsidiariedade, mas na aplica\u00e7\u00e3o do princ\u00edpio da consun\u00e7\u00e3o. A subsidiariedade se d\u00e1 quando h\u00e1 um conflito abstrato entre dois tipos penais, sendo que um deles \u00e9 mais abrangente que o outro, aplicando-se o mais abrangente:<\/p>\n\n\n\n<p>EXEMPLO: Furto x roubo: se o agente subtrai para si coisa alheia m\u00f3vel, mediante viol\u00eancia, haver\u00e1 crime de ROUBO, e n\u00e3o furto, pois a subtra\u00e7\u00e3o de coisa alheia m\u00f3vel, que \u00e9 a conduta prevista para o furto, \u00e9 um elemento de um crime complexo, que \u00e9 o roubo. Assim, se a subtra\u00e7\u00e3o ocorre com viol\u00eancia ou grave amea\u00e7a \u00e0 pessoa, n\u00e3o haver\u00e1 furto, mas roubo.<\/p>\n\n\n\n<p><strong>GABARITO: ERRADA<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"432\" height=\"354\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/06\/27205315\/image-545.png\" alt=\"\" class=\"wp-image-778380\" srcset=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/06\/27205315\/image-545.png 432w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/06\/27205315\/image-545-300x246.png 300w\" sizes=\"auto, (max-width: 432px) 100vw, 432px\" \/><\/figure>\n\n\n\n<p><strong>52. (CESPE\/2021\/DEPEN)<\/strong><\/p>\n\n\n\n<p><strong>COMENT\u00c1RIOS<\/strong><\/p>\n\n\n\n<p>Item correto, pois para a configura\u00e7\u00e3o do crime de resist\u00eancia (art. 329 do CP) \u00e9 indispens\u00e1vel que haja uma oposi\u00e7\u00e3o ATIVA, ou seja, mediante VIOL\u00caNCIA OU GRAVE AMEA\u00c7A \u00e0 pessoa.<\/p>\n\n\n\n<p><strong>GABARITO: CORRETA<\/strong><\/p>\n\n\n\n<p><strong>53. (CESPE\/2021\/DEPEN)<\/strong><\/p>\n\n\n\n<p><strong>COMENT\u00c1RIOS<\/strong><\/p>\n\n\n\n<p>Item correto, pois o art. 352 tipifica um crime de ATENTADO ou de EMPREENDIMENTO, no qual a pena ser\u00e1 a mesma para o preso que tentar fugir, mas n\u00e3o conseguir, e para o preso que tentar e conseguir fugir:<\/p>\n\n\n\n<p><em>Art. 352 &#8211; Evadir-se ou tentar evadir-se o preso ou o indiv\u00edduo submetido a medida de seguran\u00e7a detentiva, usando de viol\u00eancia contra a pessoa:<\/em><\/p>\n\n\n\n<p><em>Pena &#8211; deten\u00e7\u00e3o, de tr\u00eas meses a um ano, al\u00e9m da pena correspondente \u00e0 viol\u00eancia.<\/em><\/p>\n\n\n\n<p>Frise-se, por\u00e9m, que s\u00f3 h\u00e1 tal delito quando a fuga se d\u00e1 com viol\u00eancia \u00e0 pessoa.<\/p>\n\n\n\n<p>Como a quest\u00e3o n\u00e3o entrou nesse m\u00e9rito, entendo que est\u00e1 correta. Todavia, a reda\u00e7\u00e3o \u00e9 ruim, e d\u00e1 margem para discuss\u00f5es.<\/p>\n\n\n\n<p><strong>GABARITO: CORRETA<\/strong><\/p>\n\n\n\n<p><strong>54. (CESPE\/2021\/DEPEN)<\/strong><\/p>\n\n\n\n<p><strong>COMENT\u00c1RIOS<\/strong><\/p>\n\n\n\n<p>Item errado, pois havendo emprego de arma de fogo de uso permitido haver\u00e1 majorante prevista no art. 157, \u00a72\u00ba-A, I do CP (aumento de 2\/3), e havendo emprego de arma de fogo de uso restrito ou proibido o aumento ser\u00e1 de 2x (pena em dobro), na forma do art. 157, \u00a72\u00ba-B do CP.<\/p>\n\n\n\n<p>Todavia, temos aqui mais uma reda\u00e7\u00e3o ruim, pois, de fato, nos dois casos haver\u00e1 crime de roubo, ou seja, realmente a natureza da arma empregada n\u00e3o vai influenciar na exist\u00eancia, ou n\u00e3o, de um ROUBO, mas ir\u00e1 repercutir na tipifica\u00e7\u00e3o exata da conduta.<\/p>\n\n\n\n<p><strong>GABARITO: ERRADA<\/strong><\/p>\n\n\n\n<p>&nbsp;__________________<\/p>\n\n\n\n<p>Se voc\u00ea quer conhecer mais do meu trabalho aqui no Estrat\u00e9gia Concursos, <a href=\"https:\/\/www.estrategiaconcursos.com.br\/cursosPorProfessor\/renan-araujo-3209\/\">clique aqui<\/a> e baixe, gratuitamente, as aulas demonstrativas dos meus cursos.<\/p>\n\n\n\n<p><strong>Bons estudos!<\/strong><\/p>\n\n\n\n<p><strong>Prof. Renan Araujo<\/strong><\/p>\n\n\n\n<p><strong>E-mail:&nbsp;<\/strong><a href=\"mailto:profrenanaraujo@gmail.com\"><strong>prof<\/strong><\/a><strong>renanaraujo@gmail.com<\/strong><\/p>\n\n\n\n<p><strong>Facebook:&nbsp;<\/strong><a href=\"http:\/\/www.facebook.com\/profrenanaraujoestrategia\"><strong>www.facebook.com\/profrenanaraujoestrategia<\/strong><\/a><\/p>\n\n\n\n<p><strong>Instagram:&nbsp;<\/strong><a href=\"http:\/\/www.instagram.com\/profrenanaraujo\/?hl=pt-br\"><strong>www.instagram.com\/profrenanaraujo\/?hl=pt-br<\/strong><\/a><\/p>\n\n\n\n<p><strong>Youtube:&nbsp;<\/strong><a href=\"http:\/\/www.youtube.com\/channel\/UClIFS2cyREWT35OELN8wcFQ\"><strong>www.youtube.com\/channel\/UClIFS2cyREWT35OELN8wcFQ<\/strong><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>GABARITO DEPEN &#8211; Direito Penal Ol\u00e1, pessoal Para quem n\u00e3o me conhece ainda, meu nome \u00e9 Renan Araujo e sou professor aqui no Estrat\u00e9gia Concursos, lecionando as mat\u00e9rias de Direito Penal e Processual Penal. Antes de prosseguir, convido voc\u00ea a me seguir no INSTAGRAM:&nbsp;Instagram do Prof. Renan Araujo Neste artigo vamos comentar as quest\u00f5es de [&hellip;]<\/p>\n","protected":false},"author":39,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"post_tipo":"article","footnotes":""},"categories":[1],"tags":[],"tax_estado":[],"class_list":["post-778374","post","type-post","status-publish","format-standard","hentry","category-cursos-e-concursos"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.2 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>GABARITO DEPEN - Direito Penal (extraoficial) - Prof. Renan Araujo<\/title>\n<meta name=\"description\" content=\"Coment\u00e1rios do Prof. Renan Araujo \u00e0s quest\u00f5es de direito penal do concurso do DEPEN, cuja prova foi aplicada em 27.06.2021.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/gabarito-depen-direito-penal-extraoficial\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"GABARITO DEPEN - Direito Penal (extraoficial)\" \/>\n<meta property=\"og:description\" content=\"Coment\u00e1rios do Prof. Renan Araujo \u00e0s quest\u00f5es de direito penal do concurso do DEPEN, cuja prova foi aplicada em 27.06.2021.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/gabarito-depen-direito-penal-extraoficial\/\" \/>\n<meta property=\"og:site_name\" content=\"Estrat\u00e9gia Concursos\" \/>\n<meta property=\"article:published_time\" content=\"2021-06-27T23:54:25+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-06-27T23:54:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-content\/uploads\/2021\/06\/image-542.png\" \/>\n<meta name=\"author\" content=\"Renan Araujo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:site\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Renan Araujo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/gabarito-depen-direito-penal-extraoficial\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/gabarito-depen-direito-penal-extraoficial\/\"},\"author\":{\"name\":\"Renan Araujo\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/1a7a7af72da82939a6308b2ee292162b\"},\"headline\":\"GABARITO DEPEN &#8211; Direito Penal (extraoficial)\",\"datePublished\":\"2021-06-27T23:54:25+00:00\",\"dateModified\":\"2021-06-27T23:54:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/gabarito-depen-direito-penal-extraoficial\/\"},\"wordCount\":1015,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/gabarito-depen-direito-penal-extraoficial\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-content\/uploads\/2021\/06\/image-542.png\",\"articleSection\":[\"Concursos P\u00fablicos\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/gabarito-depen-direito-penal-extraoficial\/#respond\"]}],\"copyrightYear\":\"2021\",\"copyrightHolder\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/gabarito-depen-direito-penal-extraoficial\/\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/gabarito-depen-direito-penal-extraoficial\/\",\"name\":\"GABARITO DEPEN - Direito Penal (extraoficial) - Prof. Renan Araujo\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/gabarito-depen-direito-penal-extraoficial\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/gabarito-depen-direito-penal-extraoficial\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-content\/uploads\/2021\/06\/image-542.png\",\"datePublished\":\"2021-06-27T23:54:25+00:00\",\"dateModified\":\"2021-06-27T23:54:27+00:00\",\"description\":\"Coment\u00e1rios do Prof. Renan Araujo \u00e0s quest\u00f5es de direito penal do concurso do DEPEN, cuja prova foi aplicada em 27.06.2021.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/gabarito-depen-direito-penal-extraoficial\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/gabarito-depen-direito-penal-extraoficial\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/gabarito-depen-direito-penal-extraoficial\/#primaryimage\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/06\/27205238\/image-542.png\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/06\/27205238\/image-542.png\",\"width\":434,\"height\":245},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/gabarito-depen-direito-penal-extraoficial\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"GABARITO DEPEN &#8211; Direito Penal (extraoficial)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"name\":\"Estrat\u00e9gia Concursos\",\"description\":\"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.\",\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\",\"name\":\"Estrat\u00e9gia Concursos\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"width\":230,\"height\":60,\"caption\":\"Estrat\u00e9gia Concursos\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/EstratConcursos\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/1a7a7af72da82939a6308b2ee292162b\",\"name\":\"Renan Araujo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/ca6cb9ba5a547fbe93c05c63d6103dff6c2566555a601f1efb8590a69fb9ed76?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/ca6cb9ba5a547fbe93c05c63d6103dff6c2566555a601f1efb8590a69fb9ed76?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/ca6cb9ba5a547fbe93c05c63d6103dff6c2566555a601f1efb8590a69fb9ed76?s=96&d=mm&r=g\",\"caption\":\"Renan Araujo\"},\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/renanaraujoestrategiaconcursos-com-br\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"GABARITO DEPEN - Direito Penal (extraoficial) - Prof. Renan Araujo","description":"Coment\u00e1rios do Prof. Renan Araujo \u00e0s quest\u00f5es de direito penal do concurso do DEPEN, cuja prova foi aplicada em 27.06.2021.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.estrategiaconcursos.com.br\/blog\/gabarito-depen-direito-penal-extraoficial\/","og_locale":"pt_BR","og_type":"article","og_title":"GABARITO DEPEN - Direito Penal (extraoficial)","og_description":"Coment\u00e1rios do Prof. Renan Araujo \u00e0s quest\u00f5es de direito penal do concurso do DEPEN, cuja prova foi aplicada em 27.06.2021.","og_url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/gabarito-depen-direito-penal-extraoficial\/","og_site_name":"Estrat\u00e9gia Concursos","article_published_time":"2021-06-27T23:54:25+00:00","article_modified_time":"2021-06-27T23:54:27+00:00","og_image":[{"url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-content\/uploads\/2021\/06\/image-542.png","type":"","width":"","height":""}],"author":"Renan Araujo","twitter_card":"summary_large_image","twitter_creator":"@EstratConcursos","twitter_site":"@EstratConcursos","twitter_misc":{"Escrito por":"Renan Araujo","Est. tempo de leitura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/gabarito-depen-direito-penal-extraoficial\/#article","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/gabarito-depen-direito-penal-extraoficial\/"},"author":{"name":"Renan Araujo","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/1a7a7af72da82939a6308b2ee292162b"},"headline":"GABARITO DEPEN &#8211; Direito Penal (extraoficial)","datePublished":"2021-06-27T23:54:25+00:00","dateModified":"2021-06-27T23:54:27+00:00","mainEntityOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/gabarito-depen-direito-penal-extraoficial\/"},"wordCount":1015,"commentCount":0,"publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/gabarito-depen-direito-penal-extraoficial\/#primaryimage"},"thumbnailUrl":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-content\/uploads\/2021\/06\/image-542.png","articleSection":["Concursos P\u00fablicos"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/gabarito-depen-direito-penal-extraoficial\/#respond"]}],"copyrightYear":"2021","copyrightHolder":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/gabarito-depen-direito-penal-extraoficial\/","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/gabarito-depen-direito-penal-extraoficial\/","name":"GABARITO DEPEN - Direito Penal (extraoficial) - Prof. Renan Araujo","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/gabarito-depen-direito-penal-extraoficial\/#primaryimage"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/gabarito-depen-direito-penal-extraoficial\/#primaryimage"},"thumbnailUrl":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-content\/uploads\/2021\/06\/image-542.png","datePublished":"2021-06-27T23:54:25+00:00","dateModified":"2021-06-27T23:54:27+00:00","description":"Coment\u00e1rios do Prof. Renan Araujo \u00e0s quest\u00f5es de direito penal do concurso do DEPEN, cuja prova foi aplicada em 27.06.2021.","breadcrumb":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/gabarito-depen-direito-penal-extraoficial\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/gabarito-depen-direito-penal-extraoficial\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/gabarito-depen-direito-penal-extraoficial\/#primaryimage","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/06\/27205238\/image-542.png","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/06\/27205238\/image-542.png","width":434,"height":245},{"@type":"BreadcrumbList","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/gabarito-depen-direito-penal-extraoficial\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.estrategiaconcursos.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"GABARITO DEPEN &#8211; Direito Penal (extraoficial)"}]},{"@type":"WebSite","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","name":"Estrat\u00e9gia Concursos","description":"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.","publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization","name":"Estrat\u00e9gia Concursos","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","width":230,"height":60,"caption":"Estrat\u00e9gia Concursos"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/EstratConcursos"]},{"@type":"Person","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/1a7a7af72da82939a6308b2ee292162b","name":"Renan Araujo","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/ca6cb9ba5a547fbe93c05c63d6103dff6c2566555a601f1efb8590a69fb9ed76?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ca6cb9ba5a547fbe93c05c63d6103dff6c2566555a601f1efb8590a69fb9ed76?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ca6cb9ba5a547fbe93c05c63d6103dff6c2566555a601f1efb8590a69fb9ed76?s=96&d=mm&r=g","caption":"Renan Araujo"},"url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/renanaraujoestrategiaconcursos-com-br\/"}]}},"_links":{"self":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/778374","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/users\/39"}],"replies":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/comments?post=778374"}],"version-history":[{"count":1,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/778374\/revisions"}],"predecessor-version":[{"id":778388,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/778374\/revisions\/778388"}],"wp:attachment":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media?parent=778374"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/categories?post=778374"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tags?post=778374"},{"taxonomy":"tax_estado","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tax_estado?post=778374"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}