{"id":755304,"date":"2021-06-08T15:35:00","date_gmt":"2021-06-08T18:35:00","guid":{"rendered":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?p=755304"},"modified":"2021-06-14T14:13:59","modified_gmt":"2021-06-14T17:13:59","slug":"como-declarar-o-icms-st-na-nota-fiscal-eletronica","status":"publish","type":"post","link":"https:\/\/www.estrategiaconcursos.com.br\/blog\/como-declarar-o-icms-st-na-nota-fiscal-eletronica\/","title":{"rendered":"Como declarar o ICMS ST na Nota Fiscal Eletr\u00f4nica"},"content":{"rendered":"\n<p>Ol\u00e1, pessoal! Ao abordar o ICMS ST na Nota Fiscal Eletr\u00f4nica, falaremos sobre dois temas superimportantes no mundo fiscal. Prova disso \u00e9 que no rec\u00e9m-publicado <a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-sefaz-ce\/\" target=\"_blank\" rel=\"noreferrer noopener\">Edital<\/a> da <a href=\"https:\/\/www.estrategiaconcursos.com.br\/cursosPorConcurso\/sefaz-ce\/?utm_source=google&amp;utm_medium=cpc&amp;utm_campaign=ec-fis-vd-gsh-sefazce-x-x&amp;gclid=Cj0KCQjwna2FBhDPARIsACAEc_XNDeqjRfUQijHvreNIwPz1Lf9nGYDGClcRl97n1EAW4pt-R4mU3Z0aAkMOEALw_wcB\" target=\"_blank\" rel=\"noreferrer noopener\">Sefaz CE<\/a>, os dois assuntos foram cobrados em conjunto no seguinte item da mat\u00e9ria AUDITORIA FISCAL: <em>40 &#8211; Cotejamento do ICMS devido nas opera\u00e7\u00f5es submetidas \u00e0 substitui\u00e7\u00e3o tribut\u00e1ria e o declarado no documento fiscal<\/em>.<\/p>\n\n\n\n<p>O primeiro tema \u00e9 a Substitui\u00e7\u00e3o Tribut\u00e1ria (ST), mecanismo previsto na legisla\u00e7\u00e3o do ICMS que <strong>transfere<\/strong> a obriga\u00e7\u00e3o pelo recolhimento do imposto a um sujeito distinto do que deu origem ao fato gerador. O intuito desse regime \u00e9 <strong>facilitar<\/strong> os processos de <strong>fiscaliza\u00e7\u00e3o<\/strong> e <strong>arrecada\u00e7\u00e3o<\/strong> do ICMS, por isso ele \u00e9 bastante explorado pelas Administra\u00e7\u00f5es Tribut\u00e1rias. &nbsp;<\/p>\n\n\n\n<p>Quem tamb\u00e9m gosta muito desse assunto s\u00e3o as bancas de concurso, inclusive para as quest\u00f5es de provas discursivas; ent\u00e3o, \u00e9 importante estar afiado n\u00e3o s\u00f3 nos c\u00e1lculos, mas tamb\u00e9m na descri\u00e7\u00e3o dos principais conceitos e na argumenta\u00e7\u00e3o sobre sua import\u00e2ncia e utiliza\u00e7\u00e3o.<\/p>\n\n\n\n<p>Outro tema de grande relev\u00e2ncia s\u00e3o os documentos fiscais eletr\u00f4nicos, particularmente a Nota Fiscal Eletr\u00f4nica (NF-e), que \u00e9 o mais importante deles. No contexto da ST, tanto os substitutos quanto os substitu\u00eddos s\u00e3o obrigados a emitir o documento, cada um seguindo particularidades explicadas adiante.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-os-participantes-envolvidos-icms-st-na-nota-eletr-nica\">Os participantes envolvidos \u2013 ICMS ST na Nota Eletr\u00f4nica<\/h2>\n\n\n\n<p>A Lei Complementar n\u00ba 87, de 1996, conhecida como Lei Kandir, traz a seguinte previs\u00e3o:<\/p>\n\n\n\n<p><em>Art. 6\u00ba <strong>Lei<\/strong> estadual poder\u00e1 atribuir a <strong>contribuinte<\/strong> do imposto ou a <strong>deposit\u00e1rio<\/strong> a qualquer t\u00edtulo a responsabilidade pelo seu pagamento, hip\u00f3tese em que assumir\u00e1 a condi\u00e7\u00e3o de <strong>substituto tribut\u00e1rio<\/strong>.<\/em><\/p>\n\n\n\n<p>Surge assim a figura do <strong>substituto<\/strong> tribut\u00e1rio, que \u00e9 aquele a quem a lei atribui a <strong>responsabilidade<\/strong> pela reten\u00e7\u00e3o e\/ou recolhimento do ICMS referente ao fato gerador praticado por outro participante da opera\u00e7\u00e3o. Em geral, esse sujeito ser\u00e1 um fabricante ou importador.<\/p>\n\n\n\n<p>De forma complementar, aquele participante que pratica um fato gerador, mas, por lei, teve sua obriga\u00e7\u00e3o de recolher o imposto transferida a outrem \u00e9 o <strong>substitu\u00eddo<\/strong>. Tipicamente, trata-se de um revendedor, atacadista ou varejista.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-modalidades-de-substitui-o-tribut-ria-icms-st-na-nota-eletr-nica\">Modalidades de Substitui\u00e7\u00e3o Tribut\u00e1ria \u2013 ICMS ST na Nota Eletr\u00f4nica<\/h2>\n\n\n\n<p>O Art. 6\u00ba da Lei Kandir define ainda as modalidades de Substitui\u00e7\u00e3o Tribut\u00e1ria:<\/p>\n\n\n\n<p><em>\u00a7 1\u00ba A responsabilidade poder\u00e1 ser atribu\u00edda em rela\u00e7\u00e3o ao imposto incidente sobre uma ou mais opera\u00e7\u00f5es ou presta\u00e7\u00f5es, sejam <strong>antecedentes<\/strong>, <strong>concomitantes<\/strong> ou <strong>subsequentes<\/strong>, inclusive ao valor decorrente da <strong>diferen\u00e7a entre al\u00edquotas interna e interestadual<\/strong> nas opera\u00e7\u00f5es e presta\u00e7\u00f5es que destinem bens e servi\u00e7os <strong>a consumidor final<\/strong> localizado em outro Estado, que seja contribuinte do imposto.<\/em><\/p>\n\n\n\n<p>Assim, existem quatro modalidades de ST:<\/p>\n\n\n\n<div class=\"wp-block-image is-style-default\"><figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"621\" height=\"203\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/05\/29194839\/figura-1-1.png\" alt=\"Modalidades de Substitui\u00e7\u00e3o Tribut\u00e1ria - ICMS ST na Nota Eletr\u00f4nica\" class=\"wp-image-755342\" srcset=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/05\/29194839\/figura-1-1.png 621w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/05\/29194839\/figura-1-1-300x98.png 300w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/05\/29194839\/figura-1-1-610x199.png 610w\" sizes=\"auto, (max-width: 621px) 100vw, 621px\" \/><figcaption>Modalidades de Substitui\u00e7\u00e3o Tribut\u00e1ria<\/figcaption><\/figure><\/div>\n\n\n\n<p>Em todas elas, o substituto recolhe o ICMS correspondente a sua opera\u00e7\u00e3o, o <strong>ICMS pr\u00f3prio<\/strong>, e o imposto relativo \u00e0s opera\u00e7\u00f5es antecedentes, concomitantes ou subsequentes, que \u00e9 o chamado <strong>ICMS ST<\/strong>.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-st-das-opera-es-ou-presta-es-antecedentes\">ST das opera\u00e7\u00f5es ou presta\u00e7\u00f5es Antecedentes<\/h3>\n\n\n\n<p>Essa modalidade \u00e9 conhecida como <strong>Diferimento<\/strong> ou <strong>ST para tr\u00e1s<\/strong> e representa o adiamento do recolhimento e do lan\u00e7amento do imposto para um momento futuro. A responsabilidade pelo pagamento do imposto \u00e9 transferida para um contribuinte da etapa subsequente da cadeia comercial.<\/p>\n\n\n\n<p>O Diferimento \u00e9 adequado quando a cadeia se afunila, ou seja, quando um \u00fanico comprador concentra muitos fornecedores. Um exemplo cl\u00e1ssico \u00e9 o fornecimento de leite por parte de diversos criadores de gado a uma grande ind\u00fastria de latic\u00ednios.<\/p>\n\n\n\n<p>E como fica a emiss\u00e3o das notas fiscais? O produtor rural deve emitir a nota sem destaque do imposto. J\u00e1 a ind\u00fastria, que \u00e9 a substituta tribut\u00e1ria, pode seguir dois caminhos, a depender do <strong>momento <\/strong>em que o imposto se torna devido (defini\u00e7\u00e3o que tamb\u00e9m cabe \u00e0 legisla\u00e7\u00e3o de cada Estado):<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Emitir uma NF-e de entrada, para pagar o ICMS na entrada e j\u00e1 se creditar;<\/li><li>Emitir o documento normalmente, no momento da venda, se o imposto \u00e9 devido na sa\u00edda.<\/li><\/ul>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-st-das-opera-es-ou-presta-es-concomitantes\">ST das opera\u00e7\u00f5es ou presta\u00e7\u00f5es Concomitantes<\/h3>\n\n\n\n<p>Em tal modalidade, a Substitui\u00e7\u00e3o Tribut\u00e1ria acontece, temporalmente, no momento da ocorr\u00eancia do fato gerador. Esse \u00e9 o caso, por exemplo, da presta\u00e7\u00e3o de servi\u00e7os de transporte realizada por um <strong>Transportador Aut\u00f4nomo<\/strong>, ou por <strong>Transportadora de outro Estado, n\u00e3o inscrita no Estado de in\u00edcio da presta\u00e7\u00e3o do servi\u00e7o<\/strong>.<\/p>\n\n\n\n<p>Nessa situa\u00e7\u00e3o, a responsabilidade pelo recolhimento do ICMS correspondente \u00e0 presta\u00e7\u00e3o do servi\u00e7o de transporte \u00e9 do contratante, ou seja, do <strong>Tomador do servi\u00e7o<\/strong>, caso este seja contribuinte do ICMS no Estado do in\u00edcio da presta\u00e7\u00e3o do servi\u00e7o.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-st-do-diferencial-de-al-quotas\">ST do Diferencial de Al\u00edquotas<\/h3>\n\n\n\n<p>As seguintes condi\u00e7\u00f5es s\u00e3o necess\u00e1rias para a aplica\u00e7\u00e3o dessa modalidade. A opera\u00e7\u00e3o deve ser:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>Interestadual<\/strong>;<\/li><li><strong>Entre contribuintes<\/strong>;<\/li><li>Destinada ao <strong>consumo final<\/strong>.<\/li><\/ul>\n\n\n\n<p>\u00c9 preciso tamb\u00e9m observar o seguinte artigo da Lei Kandir:<\/p>\n\n\n\n<p><em>Art. 9\u00ba A ado\u00e7\u00e3o do regime de substitui\u00e7\u00e3o tribut\u00e1ria em opera\u00e7\u00f5es interestaduais depender\u00e1 de <strong>acordo espec\u00edfico<\/strong> celebrado pelos Estados interessados.<\/em><\/p>\n\n\n\n<p>Portanto, al\u00e9m dos tr\u00eas requisitos elencados, e da condi\u00e7\u00e3o b\u00e1sica de que a mercadoria esteja&nbsp;na lista de mercadorias sujeitas \u00e0 ST, \u00e9 necess\u00e1rio que exista acordo entre os Estados envolvidos na opera\u00e7\u00e3o.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-st-das-opera-es-ou-presta-es-subsequentes\">ST das opera\u00e7\u00f5es ou presta\u00e7\u00f5es Subsequentes<\/h3>\n\n\n\n<p>Nesse caso, tamb\u00e9m conhecido como <strong>Reten\u00e7\u00e3o de ICMS na Fonte<\/strong>, ou <strong>ST para Frente<\/strong>, o contribuinte que realiza a primeira etapa antecipa o ICMS equivalente a toda a cadeia comercial, de forma que as etapas subsequentes ficam dispensadas do recolhimento do ICMS.<\/p>\n\n\n\n<p>A ST para frente \u00e9 conveniente quando a cadeia comercial se capilariza, ou seja, h\u00e1 poucos fornecedores para muitos compradores. H\u00e1 diversas aplica\u00e7\u00f5es pr\u00e1ticas para esse caso, a exemplo das f\u00e1bricas de autom\u00f3veis vendendo para suas concession\u00e1rias, de modo que o produto se \u201cespalhe\u201d e chegue o mais pr\u00f3ximo poss\u00edvel do consumidor.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-quais-produtos-est-o-sujeitos-substitui-o-tribut-ria\">Quais produtos est\u00e3o sujeitos \u00e0 Substitui\u00e7\u00e3o Tribut\u00e1ria?<\/h2>\n\n\n\n<p>A Lei Kandir tamb\u00e9m prev\u00ea que o legislador estadual tem liberdade para estabelecer quais produtos, bens ou servi\u00e7os podem estar sujeitos a esse regime. Em um esfor\u00e7o para padronizar nacionalmente a escritura\u00e7\u00e3o das opera\u00e7\u00f5es, os Estados definiram uma sistem\u00e1tica de uniformiza\u00e7\u00e3o e identifica\u00e7\u00e3o, por meio do <a href=\"https:\/\/www.confaz.fazenda.gov.br\/legislacao\/convenios\/2015\/CV092_15\" target=\"_blank\" rel=\"noreferrer noopener\">Conv\u00eanio ICMS 92\/2015<\/a>.<\/p>\n\n\n\n<p>Assim, esse conv\u00eanio estabeleceu, em seus anexos, tabelas com listas de produtos, classificados por segmentos de mercadorias. Vale a pena se familiarizar com os produtos, mas n\u00e3o \u00e9 necess\u00e1rio decorar a lista!<\/p>\n\n\n\n<p>\u00c9 importante ressaltar que se trata de listas gen\u00e9ricas e, portanto, cada Estado tem <strong>autonomia<\/strong> para definir quais produtos ser\u00e3o de fato alcan\u00e7ados pelo regime, atrav\u00e9s da internaliza\u00e7\u00e3o total ou parcial do Conv\u00eanio em suas respectivas legisla\u00e7\u00f5es.<\/p>\n\n\n\n<p>Alguns exemplos de segmentos de mercadorias que est\u00e3o sujeitas ao ICMS ST em praticamente todos os Estados s\u00e3o: autope\u00e7as; cervejas, chopes, refrigerantes, \u00e1guas e outras bebidas; cigarros e outros produtos derivados do fumo; cimento; combust\u00edveis e lubrificantes; tintas e vernizes; ve\u00edculos automotores.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-o-c-digo-cest-icms-st-na-nota-eletr-nica\">O c\u00f3digo CEST &#8211; ICMS ST na Nota Eletr\u00f4nica<\/h2>\n\n\n\n<p>Para facilitar a identifica\u00e7\u00e3o dos produtos pass\u00edveis de sujei\u00e7\u00e3o \u00e0 Substitui\u00e7\u00e3o Tribut\u00e1ria, cada produto da lista cont\u00e9m um <em>C\u00f3digo Especificador da Substitui\u00e7\u00e3o Tribut\u00e1ria (<strong>CEST<\/strong>)<\/em>, conceito que o Conv\u00eanio ICMS 92\/2015 tamb\u00e9m instituiu.<\/p>\n\n\n\n<p>Al\u00e9m do CEST, cada produto possui uma descri\u00e7\u00e3o e a <em>Nomenclatura Comum do Mercosul baseada no Sistema Harmonizado (<strong>NCM\/SH<\/strong>)<\/em>. Esses tr\u00eas atributos \u2013 descri\u00e7\u00e3o, NCM e CEST \u2013 devem ser reproduzidos pelas legisla\u00e7\u00f5es dos Estados, para os produtos que eles desejam contemplar com a sistem\u00e1tica de ST.<\/p>\n\n\n\n<p>Desde a cria\u00e7\u00e3o do CEST, os Estados s\u00f3 podem exigir que uma cadeia de circula\u00e7\u00e3o de mercadorias fa\u00e7a parte do regime de Substitui\u00e7\u00e3o Tribut\u00e1ria se o produto estiver nas Tabelas constantes do Conv\u00eanio ICMS 92\/2015.<\/p>\n\n\n\n<p>Adicionalmente, a cria\u00e7\u00e3o desse c\u00f3digo teve impacto tamb\u00e9m na vida dos contribuintes. O CEST passou a constituir mais uma <strong>obriga\u00e7\u00e3o acess\u00f3ria<\/strong>, j\u00e1 que todas as empresas que comercializam os produtos listados devem inclu\u00ed-lo em Notas Fiscais Eletr\u00f4nicas que acobertarem opera\u00e7\u00f5es a eles relacionadas.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-vis-o-geral-da-nota-fiscal-eletr-nica\">Vis\u00e3o geral da Nota Fiscal Eletr\u00f4nica<\/h2>\n\n\n\n<p>Para compreender as etapas de emiss\u00e3o da Nota Fiscal Eletr\u00f4nica, \u00e9 preciso conhecer tr\u00eas conceitos b\u00e1sicos, que ser\u00e3o explicados a seguir.<\/p>\n\n\n\n<p>O <strong><em>layout<\/em><\/strong> da Nota Fiscal Eletr\u00f4nica \u00e9 previsto no <em>Anexo I &#8211; Leiaute e Regra de Valida\u00e7\u00e3o &#8211; NF-e e NFC-e<\/em> do <em>Manual de Orienta\u00e7\u00e3o do Contribuinte \u2013 MOC, Vers\u00e3o 7.0<\/em>, estabelecido no <a href=\"https:\/\/www.confaz.fazenda.gov.br\/legislacao\/atos\/2020\/ato-cotepe-icms-69-20\" target=\"_blank\" rel=\"noreferrer noopener\">Ato COTEPE 69\/ 2020<\/a>. De forma bastante resumida, esse documento especifica todos os campos que devem ser preenchidos em uma Nota Fiscal, seguindo uma s\u00e9rie de regras e condi\u00e7\u00f5es.<\/p>\n\n\n\n<p>As defini\u00e7\u00f5es estabelecidas no <em>layout<\/em> s\u00e3o ent\u00e3o traduzidas para um <strong>arquivo XML<\/strong>, que \u00e9 o formato escolhido para a Nota Fiscal Eletr\u00f4nica. Por fim, o <strong>programa emissor<\/strong> tem uma interface amig\u00e1vel, com a qual o usu\u00e1rio vai interagir para preencher todos os campos do documento que s\u00e3o necess\u00e1rios para acobertar a opera\u00e7\u00e3o a ser realizada.<\/p>\n\n\n\n<div class=\"wp-block-image is-style-default\"><figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/05\/29194925\/figura-2-1.png\" alt=\"Formato da NF-e - ICMS ST na Nota Eletr\u00f4nica\" class=\"wp-image-755343\" width=\"562\" height=\"235\" srcset=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/05\/29194925\/figura-2-1.png 808w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/05\/29194925\/figura-2-1-300x125.png 300w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/05\/29194925\/figura-2-1-768x321.png 768w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/05\/29194925\/figura-2-1-610x255.png 610w\" sizes=\"auto, (max-width: 562px) 100vw, 562px\" \/><figcaption>Formato da NF-e<\/figcaption><\/figure><\/div>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-o-layout-da-nota-fiscal-eletr-nica\">O <em>layout<\/em> da Nota Fiscal Eletr\u00f4nica<\/h2>\n\n\n\n<p>O <em>layout<\/em> da NF-e consolida as informa\u00e7\u00f5es que devem ser prestadas em <strong>grupos<\/strong>, que, por sua vez, cont\u00eam <strong>campos<\/strong> relacionados a um mesmo tema.<\/p>\n\n\n\n<p>Por exemplo, o <em>Grupo B. Identifica\u00e7\u00e3o da Nota Fiscal eletr\u00f4nica <\/em>deve ser preenchido com informa\u00e7\u00f5es b\u00e1sicas da nota, como o c\u00f3digo da Unidade da Federa\u00e7\u00e3o (UF) do emitente do documento, e a descri\u00e7\u00e3o da natureza da opera\u00e7\u00e3o. A seguir, outros grupos:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Grupo A. Dados da Nota Fiscal eletr\u00f4nica<\/li><li>Grupo BA. Documento Fiscal Referenciado<\/li><li>Grupo C. Identifica\u00e7\u00e3o do Emitente da Nota Fiscal eletr\u00f4nica<\/li><li>Grupo E. Identifica\u00e7\u00e3o do Destinat\u00e1rio da Nota Fiscal eletr\u00f4nica<\/li><\/ul>\n\n\n\n<p>Para cada <strong>item<\/strong> de uma NF-e, o contribuinte deve preencher os campos do <em>Grupo I. Produtos e Servi\u00e7os da NF-e<\/em> do <em>layout<\/em>, que cont\u00e9m desde informa\u00e7\u00f5es mais b\u00e1sicas, como descri\u00e7\u00e3o e valor do produto, at\u00e9 detalhes mais espec\u00edficos, como os c\u00f3digos <strong>CEST<\/strong> e <strong>NCM<\/strong>.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-exemplo-num-rico-de-icms-st-na-nota-eletr-nica\">Exemplo num\u00e9rico de ICMS ST na Nota Eletr\u00f4nica<\/h2>\n\n\n\n<p>Os seguintes dados exemplificativos ser\u00e3o considerados para montar a parte da Nota Fiscal Eletr\u00f4nica correspondente \u00e0 indica\u00e7\u00e3o do ICMS ST, considerando a modalidade <strong>ST para frente<\/strong>:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Pre\u00e7o da mercadoria = R$ 10.000,00<\/li><li>IPI = R$ 3.000,00<\/li><li>Frete por conta do adquirente = R$ 500,00<\/li><li>Margem de Valor Agregado (MVA) = 70%<\/li><li>Al\u00edquota da opera\u00e7\u00e3o (interna) = 18%<\/li><\/ul>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-c-lculo-do-icms-pr-prio-icms-st-na-nota-eletr-nica\">C\u00e1lculo do ICMS pr\u00f3prio &#8211; <strong>ICMS ST na Nota Eletr\u00f4nica<\/strong><\/h3>\n\n\n\n<p>O c\u00e1lculo do ICMS pr\u00f3prio n\u00e3o tem mist\u00e9rio:<\/p>\n\n\n\n<p>ICMS = Base de C\u00e1lculo x Al\u00edquota<\/p>\n\n\n\n<p>ICMS = 10.000 x 0,18 = 1800<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-c-lculo-do-icms-st-icms-st-na-nota-eletr-nica\">C\u00e1lculo do ICMS ST &#8211; <strong>ICMS ST na Nota Eletr\u00f4nica<\/strong><\/h3>\n\n\n\n<p>A base de c\u00e1lculo do ICMS ST deve levar em conta todos os custos incorridos pelo adquirente. Assim:<\/p>\n\n\n\n<p>Custo do adquirente = 10.000 + 3.000 + 500 = 13.500<\/p>\n\n\n\n<p>A MVA deve entrar em cima desse valor:<\/p>\n\n\n\n<p>Base de c\u00e1lculo ICMS ST = Custo do adquirente x (1 + MVA%)<\/p>\n\n\n\n<p>Bse de c\u00e1lculo ICMS ST = 13500 x 1,7 = 22.950<\/p>\n\n\n\n<p>Conceitualmente, esse valor representa o pre\u00e7o da mercadoria ao consumidor final, da ponta da cadeia. Seguindo o c\u00e1lculo:<\/p>\n\n\n\n<p>ICMS = Base de C\u00e1lculo ICMS ST x Al\u00edquota<\/p>\n\n\n\n<p>ICMS = 22.950 x 0,18 = 4.131<\/p>\n\n\n\n<p>Para chegar ao ICMS ST, basta subtrair o ICMS pr\u00f3prio do valor encontrado. Assim:<\/p>\n\n\n\n<p>ICMS ST = 4.131 \u2013 1800 = 2.331<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-o-grupo-n03-grupo-tributa-o-do-icms-10-icms-st-na-nota-eletr-nica\">O <em>Grupo N03. Grupo Tributa\u00e7\u00e3o do ICMS = 10<\/em> &#8211; ICMS ST na Nota Eletr\u00f4nica<\/h2>\n\n\n\n<p>Segundo o <em>layout <\/em>da NF-e, o <strong>Grupo N03 \u2013 Grupo Tributa\u00e7\u00e3o do ICMS = 10<\/strong> se presta a informa\u00e7\u00f5es a respeito do imposto devido em opera\u00e7\u00f5es <strong>tributadas e com cobran\u00e7a do ICMS por substitui\u00e7\u00e3o tribut\u00e1ria<\/strong>. Nas figuras abaixo, mostram-se alguns dos campos desse grupo.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large is-style-default\"><img loading=\"lazy\" decoding=\"async\" width=\"887\" height=\"432\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/06\/05125455\/grupon031.png\" alt=\"Layout da NF-e - Grupo N03 - 1 - ICMS ST na Nota Eletr\u00f4nica\" class=\"wp-image-760300\" srcset=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/06\/05125455\/grupon031.png 887w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/06\/05125455\/grupon031-300x146.png 300w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/06\/05125455\/grupon031-768x374.png 768w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/06\/05125455\/grupon031-610x297.png 610w\" sizes=\"auto, (max-width: 887px) 100vw, 887px\" \/><figcaption>Layout da NF-e &#8211; Grupo N03 &#8211; 1<\/figcaption><\/figure>\n\n\n\n<div class=\"wp-block-image is-style-default\"><figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"874\" height=\"166\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/06\/05125537\/grupon032.png\" alt=\"Layout da NF-e - Grupo N03 - 2 - ICMS ST na Nota Eletr\u00f4nica\" class=\"wp-image-760304\" srcset=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/06\/05125537\/grupon032.png 874w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/06\/05125537\/grupon032-300x57.png 300w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/06\/05125537\/grupon032-768x146.png 768w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/06\/05125537\/grupon032-610x116.png 610w\" sizes=\"auto, (max-width: 874px) 100vw, 874px\" \/><figcaption>Layout da NF-e &#8211; Grupo N03 &#8211; 2<\/figcaption><\/figure><\/div>\n\n\n\n<p>A partir desse <strong><em>layout<\/em><\/strong>, \u00e9 poss\u00edvel montar o <strong>arquivo XML<\/strong>, que \u00e9 a pr\u00f3pria NF-e. A figura a seguir mostra como o <strong>programa emissor<\/strong> espelha os campos do layout. O programa utilizado foi o <a href=\"https:\/\/www.sebrae.com.br\/sites\/PortalSebrae\/ufs\/sp\/institucional\/emissor-da-nf-e,43ce5762777fa510VgnVCM1000004c00210aRCRD\" target=\"_blank\" rel=\"noreferrer noopener\">Emissor de NF-e gratuito do Sebrae<\/a>.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large is-style-default\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"330\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/05\/29195115\/figura-4-1-1024x330.png\" alt=\"Programa emissor de NF-e\" class=\"wp-image-755345\" srcset=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/05\/29195115\/figura-4-1-1024x330.png 1024w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/05\/29195115\/figura-4-1-300x97.png 300w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/05\/29195115\/figura-4-1-768x247.png 768w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/05\/29195115\/figura-4-1-610x196.png 610w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/05\/29195115\/figura-4-1.png 1062w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption>Programa emissor de NF-e<\/figcaption><\/figure>\n\n\n\n<p>Ap\u00f3s o preenchimento e valida\u00e7\u00e3o de todas as informa\u00e7\u00f5es, o <strong>programa emissor<\/strong> gera um <strong>arquivo XML<\/strong> e o transmite \u00e0 Sefaz autorizadora da UF do emitente da NF-e. A figura abaixo mostra o trecho do XML, correspondente ao grupo <strong>Grupo N03 \u2013 Grupo Tributa\u00e7\u00e3o do ICMS = 10<\/strong>.<\/p>\n\n\n\n<div class=\"wp-block-image is-style-default\"><figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"410\" height=\"307\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/06\/05125016\/xml.png\" alt=\"Trecho de um arquivo XML de NF-e - ICMS ST na Nota Eletr\u00f4nica\" class=\"wp-image-760294\" srcset=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/06\/05125016\/xml.png 410w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/06\/05125016\/xml-300x225.png 300w\" sizes=\"auto, (max-width: 410px) 100vw, 410px\" \/><figcaption>Trecho de um arquivo XML de NF-e<\/figcaption><\/figure><\/div>\n\n\n\n<p>Nas tr\u00eas \u00faltimas imagens, as setas de mesma cor mostram a correspond\u00eancia entre <em>layout<\/em> da NF-e, campos exigidos pelo programa emissor e arquivo XML.<\/p>\n\n\n\n<p>Por hoje \u00e9 s\u00f3, pessoal! Espero que a explica\u00e7\u00e3o tenha ajudado a revisar ST, ter uma vis\u00e3o geral da NF-e e entender como as informa\u00e7\u00f5es do c\u00e1lculo da ST migram para a NF-e.<\/p>\n\n\n\n<p>Um abra\u00e7o e at\u00e9 a pr\u00f3xima!<\/p>\n\n\n\n<p>Lara Dourado<\/p>\n\n\n\n<p>Prepare-se com o melhor material e com quem mais aprova em Concursos P\u00fablicos em todo o pa\u00eds!<\/p>\n\n\n\n<div class=\"container\" id=\"boxes\">\n  <div class=\"row\">\n    <div class=\"col-sm\">\n      <div class=\"estrategia\" id=\"box-assinatura\">\n        <h3 class=\"titulo-assinatura\">Assinatura de Concursos<\/h3>\n        <p class=\"subtitulo-assinatura\">Assinatura de 1 ano ou 2 anos<\/p>\n        <div class=\"box-botao\">\n          <a class=\"btn-assinatura\" target=\"_blank\" href=\"https:\/\/www.estrategiaconcursos.com.br\/assinaturas\/\" role=\"button\" rel=\"noopener noreferrer\">ASSINE AGORA<\/a>\n        <\/div>\n      <\/div>\n      <p class=\"texto-auxiliar\"><\/p>\n    <\/div>\n    <div class=\"col-sm\">\n      <div class=\"questoes\" id=\"box-assinatura\">\n        <h3 class=\"titulo-assinatura\">Sistema de Quest\u00f5es<\/h3>\n        <p class=\"subtitulo-assinatura\">Assinatura de 1 ano ou 2 anos\n<\/p>\n        <div class=\"box-botao\">\n          <a class=\"btn-assinatura\" target=\"_blank\" href=\"https:\/\/www.estrategiaconcursos.com.br\/cursosPorConcurso\/sistema-de-questoes\/#\/\" role=\"button\" rel=\"noopener noreferrer\">ASSINE AGORA<\/a>\n        <\/div>\n      <\/div>\n      <p class=\"texto-auxiliar\"><\/p>\n    <\/div>\n  <\/div>\n<\/div>\n\n\n\n<div class=\"container\" id=\"boxes\">\n  <div class=\"row\">\n\n    <div class=\"col-sm\" id=\"boxes-concursos\">\n      <div style=\"background-color: #005DAD;\" class=\"conteudo-concursos\" id=\"box-concursos\">\n        <h3 class=\"titulo-assinatura\">Concursos Abertos<\/h3>\n        <p class=\"subtitulo-assinatura\">mais de 15 mil vagas<\/p>\n        <div class=\"box-botao\">\n          <a class=\"btn-assinatura\" target=\"_blank\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-abertos\/\" role=\"button\" rel=\"noopener noreferrer\">Conhe\u00e7a Agora<\/a>\n        <\/div>\n      <\/div>\n    <\/div>\n\n    \n\n    <div class=\"col-sm\" id=\"boxes-concursos\">\n      <div style=\"background-color: #419FF0;\" class=\"conteudo-concursos\" id=\"box-concursos\">\n        <h3 class=\"titulo-assinatura\">Concursos 2021<\/h3>\n        <p class=\"subtitulo-assinatura\">mais de 17 mil vagas<\/p>\n        <div class=\"box-botao\">\n          <a class=\"btn-assinatura\" target=\"_blank\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-2021\/\" role=\"button\" rel=\"noopener noreferrer\">Conhe\u00e7a Agora<\/a>\n        <\/div>\n      <\/div>\n    <\/div>\n\n  <\/div>\n<\/div>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ol\u00e1, pessoal! Ao abordar o ICMS ST na Nota Fiscal Eletr\u00f4nica, falaremos sobre dois temas superimportantes no mundo fiscal. Prova disso \u00e9 que no rec\u00e9m-publicado Edital da Sefaz CE, os dois assuntos foram cobrados em conjunto no seguinte item da mat\u00e9ria AUDITORIA FISCAL: 40 &#8211; Cotejamento do ICMS devido nas opera\u00e7\u00f5es submetidas \u00e0 substitui\u00e7\u00e3o tribut\u00e1ria [&hellip;]<\/p>\n","protected":false},"author":2031,"featured_media":613629,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"post_tipo":"article","footnotes":""},"categories":[1,1983],"tags":[],"tax_estado":[219964,219965,219966,219967,219968,219969,219970,219971,219972,219973,219974,219975,219976,219977,219978,219979,219980,219981,219982,219983,219984,219985,219986,219987,219988,219989,219990],"class_list":["post-755304","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cursos-e-concursos","category-fiscal-estadual","tax_estado-ac","tax_estado-al","tax_estado-am","tax_estado-ap","tax_estado-ba","tax_estado-ce","tax_estado-df","tax_estado-es","tax_estado-go","tax_estado-ma","tax_estado-mg","tax_estado-ms","tax_estado-mt","tax_estado-pa","tax_estado-pb","tax_estado-pe","tax_estado-pi","tax_estado-pr","tax_estado-rj","tax_estado-rn","tax_estado-ro","tax_estado-rr","tax_estado-rs","tax_estado-sc","tax_estado-se","tax_estado-sp","tax_estado-to"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.2 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Como declarar o ICMS ST na Nota Fiscal Eletr\u00f4nica<\/title>\n<meta name=\"description\" content=\"Revise os principais aspectos da Substitui\u00e7\u00e3o Tribut\u00e1ria e entenda como o ICMS ST aparece no layout da Nota Fiscal Eletr\u00f4nica\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/como-declarar-o-icms-st-na-nota-fiscal-eletronica\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Como declarar o ICMS ST na Nota Fiscal Eletr\u00f4nica\" \/>\n<meta property=\"og:description\" content=\"Revise os principais aspectos da Substitui\u00e7\u00e3o Tribut\u00e1ria e entenda como o ICMS ST aparece no layout da Nota Fiscal Eletr\u00f4nica\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/como-declarar-o-icms-st-na-nota-fiscal-eletronica\/\" \/>\n<meta property=\"og:site_name\" content=\"Estrat\u00e9gia Concursos\" \/>\n<meta property=\"article:published_time\" content=\"2021-06-08T18:35:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-06-14T17:13:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/11\/19172024\/ST_GERAL.png\" \/>\n\t<meta property=\"og:image:width\" content=\"718\" \/>\n\t<meta property=\"og:image:height\" content=\"390\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Lara Dourado Vasconcelos Nascimento\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:site\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Lara Dourado Vasconcelos Nascimento\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"11 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/como-declarar-o-icms-st-na-nota-fiscal-eletronica\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/como-declarar-o-icms-st-na-nota-fiscal-eletronica\/\"},\"author\":{\"name\":\"Lara Dourado Vasconcelos Nascimento\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/ed942c42839b8accae96508abec7504a\"},\"headline\":\"Como declarar o ICMS ST na Nota Fiscal Eletr\u00f4nica\",\"datePublished\":\"2021-06-08T18:35:00+00:00\",\"dateModified\":\"2021-06-14T17:13:59+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/como-declarar-o-icms-st-na-nota-fiscal-eletronica\/\"},\"wordCount\":2231,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/como-declarar-o-icms-st-na-nota-fiscal-eletronica\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/11\/19172024\/ST_GERAL.png\",\"articleSection\":[\"Concursos P\u00fablicos\",\"Fiscal - Estadual (ICMS)\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/como-declarar-o-icms-st-na-nota-fiscal-eletronica\/#respond\"]}],\"copyrightYear\":\"2021\",\"copyrightHolder\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/como-declarar-o-icms-st-na-nota-fiscal-eletronica\/\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/como-declarar-o-icms-st-na-nota-fiscal-eletronica\/\",\"name\":\"Como declarar o ICMS ST na Nota Fiscal Eletr\u00f4nica\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/como-declarar-o-icms-st-na-nota-fiscal-eletronica\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/como-declarar-o-icms-st-na-nota-fiscal-eletronica\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/11\/19172024\/ST_GERAL.png\",\"datePublished\":\"2021-06-08T18:35:00+00:00\",\"dateModified\":\"2021-06-14T17:13:59+00:00\",\"description\":\"Revise os principais aspectos da Substitui\u00e7\u00e3o Tribut\u00e1ria e entenda como o ICMS ST aparece no layout da Nota Fiscal Eletr\u00f4nica\",\"breadcrumb\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/como-declarar-o-icms-st-na-nota-fiscal-eletronica\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/como-declarar-o-icms-st-na-nota-fiscal-eletronica\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/como-declarar-o-icms-st-na-nota-fiscal-eletronica\/#primaryimage\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/11\/19172024\/ST_GERAL.png\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/11\/19172024\/ST_GERAL.png\",\"width\":718,\"height\":390,\"caption\":\"SUBSTITUI\u00c7\u00c3O TRIBUT\u00c1RIA ICMS\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/como-declarar-o-icms-st-na-nota-fiscal-eletronica\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Como declarar o ICMS ST na Nota Fiscal Eletr\u00f4nica\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"name\":\"Estrat\u00e9gia Concursos\",\"description\":\"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.\",\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\",\"name\":\"Estrat\u00e9gia Concursos\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"width\":230,\"height\":60,\"caption\":\"Estrat\u00e9gia Concursos\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/EstratConcursos\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/ed942c42839b8accae96508abec7504a\",\"name\":\"Lara Dourado Vasconcelos Nascimento\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/9d538f04fca167e02f0f7f690d97a840f4cef43d51983c7a45c635fedaf396e1?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/9d538f04fca167e02f0f7f690d97a840f4cef43d51983c7a45c635fedaf396e1?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/9d538f04fca167e02f0f7f690d97a840f4cef43d51983c7a45c635fedaf396e1?s=96&d=mm&r=g\",\"caption\":\"Lara Dourado Vasconcelos Nascimento\"},\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/laradvascgmail-com\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Como declarar o ICMS ST na Nota Fiscal Eletr\u00f4nica","description":"Revise os principais aspectos da Substitui\u00e7\u00e3o Tribut\u00e1ria e entenda como o ICMS ST aparece no layout da Nota Fiscal Eletr\u00f4nica","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.estrategiaconcursos.com.br\/blog\/como-declarar-o-icms-st-na-nota-fiscal-eletronica\/","og_locale":"pt_BR","og_type":"article","og_title":"Como declarar o ICMS ST na Nota Fiscal Eletr\u00f4nica","og_description":"Revise os principais aspectos da Substitui\u00e7\u00e3o Tribut\u00e1ria e entenda como o ICMS ST aparece no layout da Nota Fiscal Eletr\u00f4nica","og_url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/como-declarar-o-icms-st-na-nota-fiscal-eletronica\/","og_site_name":"Estrat\u00e9gia Concursos","article_published_time":"2021-06-08T18:35:00+00:00","article_modified_time":"2021-06-14T17:13:59+00:00","og_image":[{"width":718,"height":390,"url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/11\/19172024\/ST_GERAL.png","type":"image\/png"}],"author":"Lara Dourado Vasconcelos Nascimento","twitter_card":"summary_large_image","twitter_creator":"@EstratConcursos","twitter_site":"@EstratConcursos","twitter_misc":{"Escrito por":"Lara Dourado Vasconcelos Nascimento","Est. tempo de leitura":"11 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/como-declarar-o-icms-st-na-nota-fiscal-eletronica\/#article","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/como-declarar-o-icms-st-na-nota-fiscal-eletronica\/"},"author":{"name":"Lara Dourado Vasconcelos Nascimento","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/ed942c42839b8accae96508abec7504a"},"headline":"Como declarar o ICMS ST na Nota Fiscal Eletr\u00f4nica","datePublished":"2021-06-08T18:35:00+00:00","dateModified":"2021-06-14T17:13:59+00:00","mainEntityOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/como-declarar-o-icms-st-na-nota-fiscal-eletronica\/"},"wordCount":2231,"commentCount":0,"publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/como-declarar-o-icms-st-na-nota-fiscal-eletronica\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/11\/19172024\/ST_GERAL.png","articleSection":["Concursos P\u00fablicos","Fiscal - Estadual (ICMS)"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/como-declarar-o-icms-st-na-nota-fiscal-eletronica\/#respond"]}],"copyrightYear":"2021","copyrightHolder":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/como-declarar-o-icms-st-na-nota-fiscal-eletronica\/","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/como-declarar-o-icms-st-na-nota-fiscal-eletronica\/","name":"Como declarar o ICMS ST na Nota Fiscal Eletr\u00f4nica","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/como-declarar-o-icms-st-na-nota-fiscal-eletronica\/#primaryimage"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/como-declarar-o-icms-st-na-nota-fiscal-eletronica\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/11\/19172024\/ST_GERAL.png","datePublished":"2021-06-08T18:35:00+00:00","dateModified":"2021-06-14T17:13:59+00:00","description":"Revise os principais aspectos da Substitui\u00e7\u00e3o Tribut\u00e1ria e entenda como o ICMS ST aparece no layout da Nota Fiscal Eletr\u00f4nica","breadcrumb":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/como-declarar-o-icms-st-na-nota-fiscal-eletronica\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/como-declarar-o-icms-st-na-nota-fiscal-eletronica\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/como-declarar-o-icms-st-na-nota-fiscal-eletronica\/#primaryimage","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/11\/19172024\/ST_GERAL.png","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/11\/19172024\/ST_GERAL.png","width":718,"height":390,"caption":"SUBSTITUI\u00c7\u00c3O TRIBUT\u00c1RIA ICMS"},{"@type":"BreadcrumbList","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/como-declarar-o-icms-st-na-nota-fiscal-eletronica\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.estrategiaconcursos.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Como declarar o ICMS ST na Nota Fiscal Eletr\u00f4nica"}]},{"@type":"WebSite","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","name":"Estrat\u00e9gia Concursos","description":"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.","publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization","name":"Estrat\u00e9gia Concursos","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","width":230,"height":60,"caption":"Estrat\u00e9gia Concursos"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/EstratConcursos"]},{"@type":"Person","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/ed942c42839b8accae96508abec7504a","name":"Lara Dourado Vasconcelos Nascimento","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/9d538f04fca167e02f0f7f690d97a840f4cef43d51983c7a45c635fedaf396e1?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/9d538f04fca167e02f0f7f690d97a840f4cef43d51983c7a45c635fedaf396e1?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9d538f04fca167e02f0f7f690d97a840f4cef43d51983c7a45c635fedaf396e1?s=96&d=mm&r=g","caption":"Lara Dourado Vasconcelos Nascimento"},"url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/laradvascgmail-com\/"}]}},"_links":{"self":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/755304","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/users\/2031"}],"replies":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/comments?post=755304"}],"version-history":[{"count":12,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/755304\/revisions"}],"predecessor-version":[{"id":766500,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/755304\/revisions\/766500"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media\/613629"}],"wp:attachment":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media?parent=755304"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/categories?post=755304"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tags?post=755304"},{"taxonomy":"tax_estado","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tax_estado?post=755304"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}