{"id":739452,"date":"2025-04-24T06:20:00","date_gmt":"2025-04-24T09:20:00","guid":{"rendered":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?p=739452"},"modified":"2025-12-12T13:30:34","modified_gmt":"2025-12-12T16:30:34","slug":"concurso-ufpb","status":"publish","type":"post","link":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-ufpb\/","title":{"rendered":"Concurso UFPB: resultado final homologado!"},"content":{"rendered":"<p><center><a id=\"cta-icon\" href=\"https:\/\/sndflw.com\/i\/ufpb-grupo\" target=\"_blank\" style=\"background:#29a61a; display:inline-flex; align-items:center; padding:10px 15px; border-radius:6px; color:#fff; text-decoration:none; font-weight:500; font-size:15px;\"><img decoding=\"async\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/12\/07154107\/whatsapp_13851.png\" alt=\"\" style=\"width:20px; height:20px; margin-right:8px;\"><span>Acesse agora o Grupo de Estudos para o Concurso UFPB<\/span><\/a><\/center><\/p>\n\n\n\n<p>Os candidatos do<strong> concurso da<\/strong> <span><a style=\"font-weight: bold;\" href=\"https:\/\/www.estrategiaconcursos.com.br\/cursos\/concurso\/\" target=\"_blank\" rel=\"noreferrer noopener\">Universidade Federal da Para\u00edba<\/a><b> (UFPB)<\/b><\/span> foram avaliados por etapas objetivas e pr\u00e1ticas em 9 de fevereiro. E agora, o <strong>resultado final do concurso est\u00e1 homologado!<\/strong><\/p>\n\n\n\n<p>Foram registrados <a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-ufpb-inscritos\/\">32.181 inscritos<\/a> para realiza\u00e7\u00e3o das provas objetivas do certame. <\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/03\/24061742\/homologacao-do-resultado-final-ufpb.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">Resultado final homologado<\/a>;<\/li>\n\n\n\n<li><a href=\"https:\/\/anexos.cdn.selecao.net.br\/uploads\/747\/concursos\/473\/anexos\/3ef104dc-c79f-48bb-b6dc-43c9d6590e8f.pdf\">Resultado definitivos da objetiva geral<\/a>;<\/li>\n\n\n\n<li><a href=\"https:\/\/anexos.cdn.selecao.net.br\/uploads\/747\/concursos\/473\/anexos\/12952aa5-7e20-4ac2-89e0-36bf79e34549.pdf\">Resultado definitivos da objetiva para candidatos negros<\/a>;<\/li>\n\n\n\n<li><a href=\"https:\/\/anexos.cdn.selecao.net.br\/uploads\/747\/concursos\/473\/anexos\/479226cf-74e9-4647-b2b8-b257f9043e8d.pdf\">Resultado definitivos da objetiva para candidatos Pcd<\/a>;<\/li>\n\n\n\n<li><a href=\"https:\/\/concursos.ibfc.org.br\/informacoes\/473\/\">Gabaritos<\/a>.<\/li>\n<\/ul>\n\n\n\n<p>O edital ofertou de <strong>116 vagas<\/strong> de n\u00edveis m\u00e9dio\/t\u00e9cnico e superior para <strong>T\u00e9cnico-Administrativo em Educa\u00e7\u00e3o<\/strong>, em diversas especialidades!<\/p>\n\n\n\n<p>As oportunidades foram de n\u00edvel m\u00e9dio e superior de forma\u00e7\u00e3o com sal\u00e1rio<strong> inicial de at\u00e9 R$ 4.556,92<\/strong> mais benef\u00edcios.<\/p>\n\n\n\n<p>Confira todos os detalhes ao longo do artigo!<\/p>\n\n\n\n<ul class=\"wp-block-list has-very-light-gray-to-cyan-bluish-gray-gradient-background has-background\">\n<li><strong>Universidade Federal da Para\u00edba &#8211; UFPB<\/strong><\/li>\n\n\n\n<li><strong>Status:<\/strong> homologado<\/li>\n\n\n\n<li><strong>Banca:&nbsp;<\/strong><a href=\"https:\/\/concursos.ibfc.org.br\/index\/1\/\" target=\"_blank\" rel=\"noreferrer noopener\">IBFC<\/a><\/li>\n\n\n\n<li><strong>Vagas:&nbsp;<\/strong>116<\/li>\n\n\n\n<li><strong>Sal\u00e1rio<\/strong>: at\u00e9 R$ 4.556,92 + benef\u00edcios<\/li>\n\n\n\n<li><strong>Edital:<\/strong> <a href=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/10\/04063622\/edital-no-134-1o-de-novembro-de-2024-edital-no-134-1o-de-novembro-de-2024-dou-imprensa-nacional.pdf\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">UFPB<\/a> | <a href=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/12\/16204450\/ref.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">Retifica\u00e7\u00e3o<\/a><\/li>\n<\/ul>\n\n\n\n<p>Acompanhe pelos t\u00f3picos abaixo as informa\u00e7\u00f5es do <strong>concurso UFPB<\/strong>:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"#atual\">Situa\u00e7\u00e3o atual<\/a>\n<ul class=\"wp-block-list\">\n<li><a href=\"#principais-datas\">Principais datas<\/a><\/li>\n\n\n\n<li><a href=\"#resultados-do-concurso-ufpb\">Resultados<\/a><\/li>\n\n\n\n<li><a href=\"#h-demanda-de-inscritos\">Inscritos<\/a><\/li>\n\n\n\n<li><a href=\"#h-retificacoes\">Retifica\u00e7\u00f5es<\/a><\/li>\n<\/ul>\n<\/li>\n\n\n\n<li><a href=\"#cargos-e-vagas\">Cargos e vagas<\/a><\/li>\n\n\n\n<li><a href=\"#remuneracoes\">Remunera\u00e7\u00f5es<\/a><\/li>\n\n\n\n<li><a href=\"#requisitos\">Requisitos<\/a><\/li>\n\n\n\n<li><a href=\"#etapas-e-provas\">Etapas e provas<\/a><\/li>\n\n\n\n<li><a href=\"#h-ultimo-concurso-ufpb\">\u00daltimo concurso<\/a>\n<ul class=\"wp-block-list\">\n<li><a href=\"#etapas\">Provas e etapas<\/a><\/li>\n<\/ul>\n<\/li>\n\n\n\n<li><a href=\"#cursos\">Cursos e Assinaturas<\/a><\/li>\n\n\n\n<li><a href=\"#ficha\">Ficha T\u00e9cnica<\/a><\/li>\n<\/ul>\n\n\n\n<div class=\"col-sm\">\n      <div class=\"banner-estrategia\" id=\"box-assinatura\">\n        <h2 class=\"titulo-assinatura\"><span style=\"color:#fff!important; font-size: 2.5rem; font-weight: 500!important; margin-bottom: 5px!important; margin-top: 0;\">Cursos para Concurso UFPB<\/span><\/h2>\n        <p class=\"subtitulo-assinatura\">Conhe\u00e7a os cursos<\/p>\n        <div class=\"box-botao\">\n          <a class=\"btn-assinatura\" target=\"_blank\" href=\"https:\/\/www.estrategiaconcursos.com.br\/cursos\/concurso\/\" role=\"button\" rel=\"noopener noreferrer\">Conhe\u00e7a mais<\/a>\n        <\/div>\n      <\/div>\n      <p class=\"texto-auxiliar\">Prepare-se com o melhor material e com quem mais aprova em Concursos P\u00fablicos em todo o pa\u00eds.<\/p>\n    <\/div>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"atual\">Concurso UFPB: situa\u00e7\u00e3o atual<\/h2>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-principais-datas\">Principais datas <\/h3>\n\n\n\n<ul class=\"wp-block-list has-very-light-gray-to-cyan-bluish-gray-gradient-background has-background\">\n<li><strong>Inscri\u00e7\u00f5es:<\/strong><s> 18\/11 a 23\/12<\/s><\/li>\n\n\n\n<li><strong>Isen\u00e7\u00e3o:<\/strong> <s>18 a 20\/11<\/s><\/li>\n\n\n\n<li><strong>\u00daltimo dia pagamento taxa<\/strong>: <s>23\/12<\/s><\/li>\n\n\n\n<li><strong>Prova: <\/strong><s>09\/02\/2025<\/s><\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-resultados-do-concurso-ufpb\">Resultados do concurso UFPB<\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/03\/24061742\/homologacao-do-resultado-final-ufpb.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">Resultado final homologado<\/a>;<\/li>\n\n\n\n<li><a href=\"https:\/\/anexos.cdn.selecao.net.br\/uploads\/747\/concursos\/473\/anexos\/3ef104dc-c79f-48bb-b6dc-43c9d6590e8f.pdf\">Resultado definitivos da objetiva geral<\/a>;<\/li>\n\n\n\n<li><a href=\"https:\/\/anexos.cdn.selecao.net.br\/uploads\/747\/concursos\/473\/anexos\/12952aa5-7e20-4ac2-89e0-36bf79e34549.pdf\">Resultado definitivos da objetiva para candidatos negros<\/a>;<\/li>\n\n\n\n<li><a href=\"https:\/\/anexos.cdn.selecao.net.br\/uploads\/747\/concursos\/473\/anexos\/479226cf-74e9-4647-b2b8-b257f9043e8d.pdf\">Resultado definitivos da objetiva para candidatos Pcd<\/a>;<\/li>\n\n\n\n<li><a href=\"https:\/\/concursos.ibfc.org.br\/informacoes\/473\/\">Gabaritos<\/a>.<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-demanda-de-inscritos\">Demanda de inscritos<\/h3>\n\n\n\n<p>O concurso UFPB divulgou os n\u00fameros de candidatos por vaga, <a href=\"https:\/\/www.ufpb.br\/ufpb\/contents\/noticias\/concurso-para-tecnico-administrativo-da-ufpb-tem-cerca-de-32-mil-inscritos\/WhatsAppImage20250117at11.34.34.jpeg\">totalizando 32.181 inscritos<\/a>. O cargo com maior n\u00famero de candidatos \u00e9 o de <strong>Assistente de Administra\u00e7\u00e3o <\/strong>de n\u00edvel m\u00e9dio, com <strong>48 vagas e 23.115 inscri\u00e7\u00f5es<\/strong>! <\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-retificacoes\">Retifica\u00e7\u00f5es<\/h3>\n\n\n\n<p>Entre as principais mudan\u00e7as est\u00e3o os requisitos de alguns cargos, altera\u00e7\u00f5es na Prova Pr\u00e1tica para o cargo de M\u00fasico-Viola e ajustes no conte\u00fado program\u00e1tico para a fun\u00e7\u00e3o de Bibliotec\u00e1rio Documentalista. Confira todas as altera\u00e7\u00f5es no link abaixo:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/11\/21153927\/qcjelb2pz30d8ckks0de9suz6yaeommfx1plex2r.pdf\">Retifica\u00e7\u00e3o 1<\/a>;<\/li>\n\n\n\n<li><a href=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/12\/16204450\/ref.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">Retifica\u00e7\u00e3o 2<\/a>.<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-concurso-ufpb-cargos-e-vagas\">Concurso UFPB: cargos e vagas<\/h2>\n\n\n\n<p>O concurso foi para provimento de vagas, distribu\u00eddas por cargos, conforme a seguir:<\/p>\n\n\n\n<figure class=\"wp-block-table is-style-stripes\"><table class=\"has-fixed-layout\"><tbody><tr><td>N\u00edvel<\/td><td>Classe<\/td><td>Cargo<\/td><td colspan=\"4\">Vagas<\/td><\/tr><tr><td><\/td><td><\/td><td><\/td><td>AmplaConcorr\u00eancia<\/td><td>Pessoas com Defici\u00eancia<\/td><td>Negros<\/td><td>Total<\/td><\/tr><tr><td>M\u00e9dio<\/td><td>D<\/td><td>Assistente em Administra\u00e7\u00e3o<\/td><td>35<\/td><td>3<\/td><td>10<\/td><td>48<\/td><\/tr><tr><td><\/td><td><\/td><td>T\u00e9cnico em Tecnologia da Informa\u00e7\u00e3o<\/td><td>14<\/td><td>1<\/td><td>4<\/td><td>19<\/td><\/tr><tr><td><\/td><td><\/td><td>T\u00e9cnico em Contabilidade<\/td><td>3<\/td><td>&#8211;<\/td><td>1<\/td><td>4<\/td><\/tr><tr><td><\/td><td><\/td><td>T\u00e9cnico em Enfermagem<\/td><td>2<\/td><td>&#8211;<\/td><td>&#8211;<\/td><td>2<\/td><\/tr><tr><td><\/td><td><\/td><td>T\u00e9cnico de Laborat\u00f3rio-Anatomia e Necropsia<\/td><td>1<\/td><td>&#8211;<\/td><td>&#8211;<\/td><td>1<\/td><\/tr><tr><td><\/td><td><\/td><td>T\u00e9cnico de Laborat\u00f3rio-Audiovisual<\/td><td>2<\/td><td>&#8211;<\/td><td>&#8211;<\/td><td>2<\/td><\/tr><tr><td><\/td><td><\/td><td>T\u00e9cnico de Laborat\u00f3rio-Biologia<\/td><td>1<\/td><td>&#8211;<\/td><td>&#8211;<\/td><td>1<\/td><\/tr><tr><td><\/td><td><\/td><td>T\u00e9cnico de Laborat\u00f3rio-Biot\u00e9rio<\/td><td>1<\/td><td>&#8211;<\/td><td>&#8211;<\/td><td>1<\/td><\/tr><tr><td><\/td><td><\/td><td>T\u00e9cnico de Laborat\u00f3rio-Eletr\u00f4nica<\/td><td>1<\/td><td>&#8211;<\/td><td>&#8211;<\/td><td>1<\/td><\/tr><tr><td><\/td><td><\/td><td>T\u00e9cnico de Laborat\u00f3rio-Eletrot\u00e9cnica<\/td><td>1<\/td><td>&#8211;<\/td><td>&#8211;<\/td><td>1<\/td><\/tr><tr><td><\/td><td><\/td><td>T\u00e9cnico de Laborat\u00f3rio-Gastronomia<\/td><td>1<\/td><td>&#8211;<\/td><td>&#8211;<\/td><td>1<\/td><\/tr><tr><td><\/td><td><\/td><td>T\u00e9cnico de Laborat\u00f3rio-Odontologia<\/td><td>2<\/td><td>&#8211;<\/td><td>&#8211;<\/td><td>2<\/td><\/tr><tr><td><\/td><td><\/td><td>T\u00e9cnico de Laborat\u00f3rio-Qu\u00edmica<\/td><td>2<\/td><td>&#8211;<\/td><td>&#8211;<\/td><td>2<\/td><\/tr><tr><td>Superior<\/td><td>E<\/td><td>Assistente Social<\/td><td>2<\/td><td>&#8211;<\/td><td>&#8211;<\/td><td>2<\/td><\/tr><tr><td><\/td><td><\/td><td>Analista de Tecnologia da Informa\u00e7\u00e3o<\/td><td>3<\/td><td>&#8211;<\/td><td>1<\/td><td>4<\/td><\/tr><tr><td><\/td><td><\/td><td>Bibliotec\u00e1rio Documentalista<\/td><td>3<\/td><td>&#8211;<\/td><td>1<\/td><td>4<\/td><\/tr><tr><td><\/td><td><\/td><td>Bi\u00f3logo<\/td><td>1<\/td><td>&#8211;<\/td><td>&#8211;<\/td><td>1<\/td><\/tr><tr><td><\/td><td><\/td><td>Economista<\/td><td>1<\/td><td>&#8211;<\/td><td>&#8211;<\/td><td>1<\/td><\/tr><tr><td><\/td><td><\/td><td>Enfermeiro<\/td><td>1<\/td><td>&#8211;<\/td><td>&#8211;<\/td><td>1<\/td><\/tr><tr><td><\/td><td><\/td><td>Engenheiro-Telecomunica\u00e7\u00f5es<\/td><td>1<\/td><td>&#8211;<\/td><td>&#8211;<\/td><td>1<\/td><\/tr><tr><td><\/td><td><\/td><td>Engenheiro de Seguran\u00e7a do Trabalho<\/td><td>1<\/td><td>&#8211;<\/td><td>&#8211;<\/td><td>1<\/td><\/tr><tr><td><\/td><td><\/td><td>M\u00e9dico-Cl\u00ednica M\u00e9dica<\/td><td>2<\/td><td>&#8211;<\/td><td>&#8211;<\/td><td>2<\/td><\/tr><tr><td><\/td><td><\/td><td>M\u00e9dico-Ginecologia<\/td><td>1<\/td><td>&#8211;<\/td><td>&#8211;<\/td><td>1<\/td><\/tr><tr><td><\/td><td><\/td><td>M\u00e9dico-Otorrinolaringologia<\/td><td>1<\/td><td>&#8211;<\/td><td>&#8211;<\/td><td>1<\/td><\/tr><tr><td><\/td><td><\/td><td>M\u00e9dico-Psiquiatria<\/td><td>2<\/td><td>&#8211;<\/td><td>&#8211;<\/td><td>2<\/td><\/tr><tr><td><\/td><td><\/td><td>M\u00fasico-Viola<\/td><td>1<\/td><td>&#8211;<\/td><td>&#8211;<\/td><td>1<\/td><\/tr><tr><td><\/td><td><\/td><td>Produtor Cultural<\/td><td>2<\/td><td>&#8211;<\/td><td>&#8211;<\/td><td>2<\/td><\/tr><tr><td><\/td><td><\/td><td>T\u00e9cnico em Assuntos Educacionais<\/td><td>3<\/td><td>1<\/td><td>1<\/td><td>5<\/td><\/tr><tr><td><\/td><td><\/td><td>Tecn\u00f3logo-Arqueologia<\/td><td>1<\/td><td>&#8211;<\/td><td>&#8211;<\/td><td>1<\/td><\/tr><tr><td><\/td><td><\/td><td>Tecn\u00f3logo-Secretariado Executivo<\/td><td>1<\/td><td>&#8211;<\/td><td>&#8211;<\/td><td>1<\/td><\/tr><tr><td colspan=\"3\">Total<\/td><td>93<\/td><td>5<\/td><td>18<\/td><td>116<\/td><\/tr><\/tbody><\/table><figcaption class=\"wp-element-caption\">Distribui\u00e7\u00e3o dos cargos e vagas de n\u00edveis m\u00e9dio e superior<\/figcaption><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-concurso-ufpb-remuneracoes\">Concurso UFPB: remunera\u00e7\u00f5es<\/h2>\n\n\n\n<p>O vencimento b\u00e1sico correspondente \u00e0 classe, n\u00edvel de capacita\u00e7\u00e3o e padr\u00f5es iniciais dos cargos s\u00e3o os estabelecidos a seguir:<\/p>\n\n\n\n<figure class=\"wp-block-table is-style-stripes\"><table class=\"has-fixed-layout\"><tbody><tr><td>Classe\/N\u00edvel<\/td><td>Vencimento b\u00e1sico<\/td><\/tr><tr><td>D &#8211; M\u00e9dio<\/td><td>R$ 2.667,19<\/td><\/tr><tr><td>E &#8211; Superior<\/td><td>R$ 4.556,92<\/td><\/tr><\/tbody><\/table><figcaption class=\"wp-element-caption\">Tabela remunerat\u00f3ria dos cargos<\/figcaption><\/figure>\n\n\n\n<p>Para todos os cargos ser\u00e1 acrescido o valor de R$ 1.000,00, relativos ao aux\u00edlio-alimenta\u00e7\u00e3o.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-concurso-ufpb-requisitos\">Concurso UFPB: requisitos<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Assistente em Administra\u00e7\u00e3o<\/strong>: Curso M\u00e9dio Profissionalizante ou M\u00e9dio Completo.<\/li>\n\n\n\n<li><strong>T\u00e9cnico em Tecnologia da Informa\u00e7\u00e3o<\/strong>: Curso M\u00e9dio Profissionalizante na \u00e1rea de Inform\u00e1tica, Tecnologia da Informa\u00e7\u00e3o ou Eletr\u00f4nica com \u00eanfase em Sistemas Computacionais, ou Ensino M\u00e9dio completo acrescido de curso t\u00e9cnico subsequente na \u00e1rea de Inform\u00e1tica, Tecnologia da Informa\u00e7\u00e3o ou Eletr\u00f4nica com \u00eanfase em Sistemas Computacionais.<\/li>\n\n\n\n<li><strong>T\u00e9cnico em Contabilidade<\/strong>: Curso M\u00e9dio Profissionalizante em Contabilidade ou M\u00e9dio completo + Curso T\u00e9cnico em Contabilidade e registro no conselho competente.<\/li>\n\n\n\n<li><strong>T\u00e9cnico em Enfermagem<\/strong>: Curso M\u00e9dio Profissionalizante em Enfermagem ou M\u00e9dio completo + Curso T\u00e9cnico em Enfermagem e registro no conselho competente.<\/li>\n\n\n\n<li><strong>T\u00e9cnico de Laborat\u00f3rio \u2013 Anatomia e Necropsia<\/strong>: Curso M\u00e9dio Profissionalizante na \u00e1rea de Necropsia ou M\u00e9dio completo + curso T\u00e9cnico em Necropsia e Registro no Conselho competente quando for exig\u00eancia para exerc\u00edcio da profiss\u00e3o.<\/li>\n\n\n\n<li><strong>T\u00e9cnico de Laborat\u00f3rio \u2013 Audiovisual<\/strong>: Curso M\u00e9dio profissionalizante na \u00e1rea de Audiovisual ou M\u00e9dio completo com curso t\u00e9cnico na \u00e1rea de Audiovisual e Registro no Conselho competente quando for exig\u00eancia para exerc\u00edcio da profiss\u00e3o.<\/li>\n\n\n\n<li><strong>T\u00e9cnico de Laborat\u00f3rio \u2013 Biologia<\/strong>: Curso M\u00e9dio Profissionalizante na \u00e1rea de Biologia ou M\u00e9dio completo + curso T\u00e9cnico na \u00e1rea de Biologia e Registro no Conselho competente quando for exig\u00eancia para exerc\u00edcio da profiss\u00e3o.<\/li>\n\n\n\n<li><strong>T\u00e9cnico de Laborat\u00f3rio \u2013 Biot\u00e9rio<\/strong>: Curso M\u00e9dio Profissionalizante na \u00c1rea de Agropecu\u00e1ria, Zootecnia, Agronomia, Veterin\u00e1ria, Biomedicina, Bioqu\u00edmica, Biot\u00e9rio ou Biotecnologia ou Curso M\u00e9dio Completo mais Curso T\u00e9cnico nas mesmas \u00e1reas e Registro no Conselho competente quando exigido.<\/li>\n\n\n\n<li><strong>T\u00e9cnico de Laborat\u00f3rio \u2013 Eletr\u00f4nica<\/strong>: Curso M\u00e9dio Profissionalizante na \u00e1rea de Eletr\u00f4nica ou M\u00e9dio completo + curso T\u00e9cnico em Eletr\u00f4nica e Registro no Conselho competente quando for exig\u00eancia para exerc\u00edcio da profiss\u00e3o.<\/li>\n\n\n\n<li><strong>T\u00e9cnico de Laborat\u00f3rio \u2013 Eletrot\u00e9cnica<\/strong>: Curso M\u00e9dio Profissionalizante na \u00e1rea de Eletrot\u00e9cnica ou M\u00e9dio completo + curso T\u00e9cnico na \u00e1rea de Eletrot\u00e9cnica e Registro no Conselho competente quando exigido.<\/li>\n\n\n\n<li><strong>T\u00e9cnico de Laborat\u00f3rio \u2013 Gastronomia<\/strong>: Curso M\u00e9dio Profissionalizante na \u00e1rea de Gastronomia ou M\u00e9dio completo + curso T\u00e9cnico em Gastronomia e Registro no Conselho competente quando exigido.<\/li>\n\n\n\n<li><strong>T\u00e9cnico de Laborat\u00f3rio \u2013 Odontologia<\/strong>: Curso M\u00e9dio Profissionalizante na \u00e1rea de Odontologia ou M\u00e9dio completo + curso T\u00e9cnico em Sa\u00fade Bucal e Registro no Conselho competente quando exigido.<\/li>\n\n\n\n<li><strong>T\u00e9cnico de Laborat\u00f3rio \u2013 Qu\u00edmica<\/strong>: Curso M\u00e9dio Profissionalizante em Qu\u00edmica ou M\u00e9dio completo + curso T\u00e9cnico em Qu\u00edmica e Registro no Conselho competente quando exigido.<\/li>\n\n\n\n<li><strong>Assistente Social<\/strong>: Curso Superior em Servi\u00e7o Social e registro no Conselho competente.<\/li>\n\n\n\n<li><strong>Analista de Tecnologia da Informa\u00e7\u00e3o<\/strong>: Curso Superior na \u00e1rea de Tecnologia da Informa\u00e7\u00e3o.<\/li>\n\n\n\n<li><strong>Bibliotec\u00e1rio Documentalista<\/strong>: Curso Superior em Biblioteconomia ou Ci\u00eancias da Informa\u00e7\u00e3o e registro no Conselho competente.<\/li>\n\n\n\n<li><strong>Bi\u00f3logo<\/strong>: Curso Superior em Ci\u00eancias Biol\u00f3gicas e registro no Conselho competente.<\/li>\n\n\n\n<li><strong>Economista<\/strong>: Curso Superior em Economia e registro no Conselho competente.<\/li>\n\n\n\n<li><strong>Enfermeiro<\/strong>: Curso Superior em Enfermagem e registro no Conselho competente.<\/li>\n\n\n\n<li><strong>Engenheiro \u2013 Telecomunica\u00e7\u00f5es<\/strong>: Curso Superior em Engenharia de Telecomunica\u00e7\u00f5es e registro no Conselho competente.<\/li>\n\n\n\n<li><strong>Engenheiro de Seguran\u00e7a do Trabalho<\/strong>: Curso Superior em Engenharia com Especializa\u00e7\u00e3o em Seguran\u00e7a do Trabalho e registro no Conselho competente.<\/li>\n\n\n\n<li><strong>M\u00e9dico \u2013 Cl\u00ednica M\u00e9dica<\/strong>: Curso Superior em Medicina com resid\u00eancia m\u00e9dica em Cl\u00ednica M\u00e9dica ou t\u00edtulo de especialista na \u00e1rea e registro no Conselho competente.<\/li>\n\n\n\n<li><strong>M\u00e9dico \u2013 Ginecologia<\/strong>: Curso Superior em Medicina com resid\u00eancia m\u00e9dica em Ginecologia e Obstetr\u00edcia ou t\u00edtulo de especialista na \u00e1rea e registro no Conselho competente.<\/li>\n\n\n\n<li><strong>M\u00e9dico \u2013 Otorrinolaringologia<\/strong>: Curso Superior em Medicina com resid\u00eancia m\u00e9dica em Otorrinolaringologia ou t\u00edtulo de especialista na \u00e1rea e registro no Conselho competente.<\/li>\n\n\n\n<li><strong>M\u00e9dico \u2013 Psiquiatria<\/strong>: Curso Superior em Medicina com resid\u00eancia m\u00e9dica em Psiquiatria ou t\u00edtulo de especialista na \u00e1rea e registro no Conselho competente.<\/li>\n\n\n\n<li><strong>M\u00fasico \u2013 Viola<\/strong>: Curso Superior em M\u00fasica com forma\u00e7\u00e3o em viola e registro no Conselho competente.<\/li>\n\n\n\n<li><strong>Produtor Cultural<\/strong>: Curso Superior em Produ\u00e7\u00e3o Cultural ou em Comunica\u00e7\u00e3o Social.<\/li>\n\n\n\n<li><strong>Tecn\u00f3logo \u2013 Arqueologia<\/strong>: Curso Superior em Arqueologia e registro no Conselho competente.<\/li>\n\n\n\n<li><strong>Tecn\u00f3logo \u2013 Secretariado Executivo<\/strong>: Curso Superior em Secretariado Executivo ou Letras.<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-concurso-ufpb-etapas-e-provas\">Concurso UFPB: etapas e provas<\/h2>\n\n\n\n<p>Os candidatos foram avaliados por meio das etapas seguintes:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Prova objetiva<\/strong>, de car\u00e1ter eliminat\u00f3rio e classificat\u00f3rio, para todos os cargos; e<\/li>\n\n\n\n<li><strong>Prova pr\u00e1tica<\/strong>, de car\u00e1ter eliminat\u00f3rio e classificat\u00f3rio, para M\u00fasico-Viola e T\u00e9cnico de Laborat\u00f3rio (Anatomia\/Necropsia, Audiovisual, Biologia, Biot\u00e9rio, Eletr\u00f4nica, Eletrot\u00e9cnica, Gastronomia, Odontologia e Qu\u00edmica).<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-prova-objetiva\">Prova objetiva<\/h3>\n\n\n\n<p>As provas objetivas foram compostas de<strong> 50 quest\u00f5es<\/strong> de m\u00faltipla escolha, sendo que cada quest\u00e3o conter\u00e1 05 alternativas e apenas 1 correta.&nbsp;<\/p>\n\n\n\n<p>Foram cobradas quest\u00f5es de portugu\u00eas, racioc\u00ednio l\u00f3gico, no\u00e7\u00f5es de inform\u00e1tica, legisla\u00e7\u00e3o e conhecimentos espec\u00edficos.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-prova-pratica\">Prova pr\u00e1tica<\/h3>\n\n\n\n<p>Somente foram convocados para a realiza\u00e7\u00e3o da Prova Pr\u00e1tica os candidatos dos cargos de M\u00fasico-Viola e T\u00e9cnico de Laborat\u00f3rio (Anatomia\/Necropsia, Audiovisual, Biologia, Biot\u00e9rio, Eletr\u00f4nica, Eletrot\u00e9cnica, Gastronomia, Odontologia e Qu\u00edmica), que foram habilitados na Prova Objetiva<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-ultimo-concurso-ufpb\">\u00daltimo concurso UFPB<\/h2>\n\n\n\n<p>Em <strong>2023<\/strong>, foram ofertadas vagas para o cargo de <a href=\"https:\/\/www.in.gov.br\/web\/dou\/-\/edital-n-50-3-de-outubro-de-2022-concurso-publico-de-provas-e-titulos-para-professor-do-ensino-basico-tecnico-e-tecnologico-ebtt-433777955\" target=\"_blank\" rel=\"noreferrer noopener\">professor<\/a>:<\/p>\n\n\n\n<figure class=\"wp-block-table is-style-stripes\"><table class=\"has-background has-fixed-layout\" style=\"background-color:#e7f5fe\"><thead><tr><th class=\"has-text-align-center\" data-align=\"center\">CARGOS<\/th><th class=\"has-text-align-center\" data-align=\"center\">VAGAS<\/th><th class=\"has-text-align-center\" data-align=\"center\">SAL\u00c1RIO<\/th><\/tr><\/thead><tbody><tr><td class=\"has-text-align-center\" data-align=\"center\">Professor<\/td><td class=\"has-text-align-center\" data-align=\"center\">01<\/td><td class=\"has-text-align-center\" data-align=\"center\">R$ 4.472,64<\/td><\/tr><\/tbody><\/table><figcaption class=\"wp-element-caption\">Cargos e vagas do edital de 2023<\/figcaption><\/figure>\n\n\n\n<p>Foi ofertado para o cargo de Professor do Ensino B\u00e1sico, T\u00e9cnico e Tecnol\u00f3gico \u2013 EBTT a remunera\u00e7\u00e3o no valor de R$ 4.472,64, podendo chegar a<strong> R$ 5.143,54<\/strong>.<\/p>\n\n\n\n<p>Al\u00e9m da remunera\u00e7\u00e3o, o candidato aprovado faz jus ao recebimento de aux\u00edlio \u2013 alimenta\u00e7\u00e3o. A sele\u00e7\u00e3o dos candidatos inscritos no edital UFPB se deu mediante aplica\u00e7\u00e3o das seguintes etapas:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Prova Escrita<\/strong>, com car\u00e1ter eliminat\u00f3rio;<\/li>\n\n\n\n<li><strong>Prova Did\u00e1tica<\/strong>, com car\u00e1ter eliminat\u00f3rio; e<\/li>\n\n\n\n<li><strong>Exame de T\u00edtulos<\/strong>, com car\u00e1ter classificat\u00f3rio.<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-center\" id=\"h-quer-saber-tudo-sobre-concursos-previstos-confira-nossos-artigos\">Quer saber tudo sobre concursos previstos?<br \/>Confira nossos artigos!<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-abertos\/\" target=\"_blank\" rel=\"noreferrer noopener\">Concursos abertos<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-educacao\/\">Concursos educa\u00e7\u00e3o<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-2025\" target=\"_blank\" rel=\"noreferrer noopener\">Concursos 2025<\/a><\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-center\" id=\"cursos\">Cursos e Assinaturas<\/h2>\n\n\n\n<p class=\"has-text-align-center\"><strong><em>Gostou dessa oportunidade&nbsp;e deseja se preparar para este concurso?<\/em><\/strong><br \/><strong><em>Esteja mais preparado com nossos cursos. Acompanhe as novidades!<\/em><\/strong><\/p>\n\n\n\n<div class=\"col-sm\">\n      <div class=\"banner-estrategia\" id=\"box-assinatura\">\n        <h3 class=\"titulo-assinatura\"><span style=\"color:#fff!important; font-size: 2.5rem; font-weight: 500!important; margin-bottom: 5px!important; margin-top: 0;\">Cursos para UFPB<\/span><\/h3>\n        <p class=\"subtitulo-assinatura\">Conhe\u00e7a os cursos<\/p>\n        <div class=\"box-botao\">\n          <a class=\"btn-assinatura\" target=\"_blank\" href=\"https:\/\/www.estrategiaconcursos.com.br\/cursos\/concurso\/\" role=\"button\" rel=\"noopener noreferrer\">Conhe\u00e7a mais<\/a>\n        <\/div>\n      <\/div>\n      <p class=\"texto-auxiliar\">Prepare-se com o melhor material e com quem mais aprova em Concursos P\u00fablicos em todo o pa\u00eds.<\/p>\n    <\/div>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"632\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/04\/27084917\/ficha-tecnica-173-1024x632.png\" alt=\"ficha t\u00e9cnica concurso UFPB\" class=\"wp-image-724003\" style=\"aspect-ratio:1.6363636363636365\" srcset=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/04\/27084917\/ficha-tecnica-173-1024x632.png 1024w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/04\/27084917\/ficha-tecnica-173-300x185.png 300w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/04\/27084917\/ficha-tecnica-173-768x474.png 768w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/04\/27084917\/ficha-tecnica-173-1536x948.png 1536w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/04\/27084917\/ficha-tecnica-173-610x377.png 610w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/04\/27084917\/ficha-tecnica-173.png 1571w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">\ufeff<\/figcaption><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"block-ba1614b5-988b-41ef-892d-f4c9f7e9dd42\">Informa\u00e7\u00f5es do concurso UFPB<\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Provas<\/strong>: <s>09\/02\/2025<\/s><\/li>\n\n\n\n<li><strong>Vagas<\/strong>: 116<\/li>\n\n\n\n<li><strong>Cargos<\/strong>: diversos<\/li>\n\n\n\n<li><strong>Banca<\/strong>: IBFC<\/li>\n\n\n\n<li><strong>Escolaridade<\/strong>: m\u00e9dio e superior<\/li>\n\n\n\n<li><strong>Edital<\/strong>: <a href=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/10\/04063622\/edital-no-134-1o-de-novembro-de-2024-edital-no-134-1o-de-novembro-de-2024-dou-imprensa-nacional.pdf\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">UFPB<\/a> | <a href=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/12\/16204450\/ref.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">Retifica\u00e7\u00e3o<\/a><\/li>\n<\/ul>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Os candidatos do concurso da Universidade Federal da Para\u00edba (UFPB) foram avaliados por etapas objetivas e pr\u00e1ticas em 9 de fevereiro. E agora, o resultado final do concurso est\u00e1 homologado! Foram registrados 32.181 inscritos para realiza\u00e7\u00e3o das provas objetivas do certame. O edital ofertou de 116 vagas de n\u00edveis m\u00e9dio\/t\u00e9cnico e superior para T\u00e9cnico-Administrativo em [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1467920,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"post_tipo":"news_page","footnotes":""},"categories":[3766],"tags":[],"tax_estado":[219978],"class_list":["post-739452","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-educacional","tax_estado-pb"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.2 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Concurso UFPB: resultado final homologado!<\/title>\n<meta name=\"description\" content=\"Concurso UFPB: edital ofertou 116 vagas para o cargo de T\u00e9cnico-Administrativo em Educa\u00e7\u00e3o. Homologado o resultado!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-ufpb\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Concurso UFPB: resultado final homologado!\" \/>\n<meta property=\"og:description\" content=\"Concurso UFPB: edital ofertou 116 vagas para o cargo de T\u00e9cnico-Administrativo em Educa\u00e7\u00e3o. Homologado o resultado!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-ufpb\/\" \/>\n<meta property=\"og:site_name\" content=\"Estrat\u00e9gia Concursos\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/EstrategiaConcursos\" \/>\n<meta property=\"article:published_time\" content=\"2025-04-24T09:20:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-12T16:30:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/09\/27151749\/ufpb.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"768\" \/>\n\t<meta property=\"og:image:height\" content=\"432\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Coordena\u00e7\u00e3o\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:site\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Coordena\u00e7\u00e3o\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-ufpb\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-ufpb\/\"},\"author\":{\"name\":\"Coordena\u00e7\u00e3o\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/b4a388c97673c5f483d72185668afa1f\"},\"headline\":\"Concurso UFPB: resultado final homologado!\",\"datePublished\":\"2025-04-24T09:20:00+00:00\",\"dateModified\":\"2025-12-12T16:30:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-ufpb\/\"},\"wordCount\":1767,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-ufpb\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/09\/27151749\/ufpb.jpg\",\"articleSection\":[\"Educa\u00e7\u00e3o\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-ufpb\/#respond\"]}],\"copyrightYear\":\"2025\",\"copyrightHolder\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-ufpb\/\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-ufpb\/\",\"name\":\"Concurso UFPB: resultado final homologado!\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-ufpb\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-ufpb\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/09\/27151749\/ufpb.jpg\",\"datePublished\":\"2025-04-24T09:20:00+00:00\",\"dateModified\":\"2025-12-12T16:30:34+00:00\",\"description\":\"Concurso UFPB: edital ofertou 116 vagas para o cargo de T\u00e9cnico-Administrativo em Educa\u00e7\u00e3o. Homologado o resultado!\",\"breadcrumb\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-ufpb\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-ufpb\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-ufpb\/#primaryimage\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/09\/27151749\/ufpb.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/09\/27151749\/ufpb.jpg\",\"width\":768,\"height\":432},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-ufpb\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Concurso UFPB: resultado final homologado!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"name\":\"Estrat\u00e9gia Concursos\",\"description\":\"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.\",\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\",\"name\":\"Estrat\u00e9gia Concursos\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"width\":230,\"height\":60,\"caption\":\"Estrat\u00e9gia Concursos\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/EstratConcursos\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/b4a388c97673c5f483d72185668afa1f\",\"name\":\"Coordena\u00e7\u00e3o\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/b720319e4c9a967eb58678d110f4fe35452fc5d5f97b202bac7b8acceb18c6ad?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/b720319e4c9a967eb58678d110f4fe35452fc5d5f97b202bac7b8acceb18c6ad?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/b720319e4c9a967eb58678d110f4fe35452fc5d5f97b202bac7b8acceb18c6ad?s=96&d=mm&r=g\",\"caption\":\"Coordena\u00e7\u00e3o\"},\"sameAs\":[\"https:\/\/www.facebook.com\/EstrategiaConcursos\",\"https:\/\/x.com\/EstratConcursos\"],\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/estrategia2013\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Concurso UFPB: resultado final homologado!","description":"Concurso UFPB: edital ofertou 116 vagas para o cargo de T\u00e9cnico-Administrativo em Educa\u00e7\u00e3o. Homologado o resultado!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-ufpb\/","og_locale":"pt_BR","og_type":"article","og_title":"Concurso UFPB: resultado final homologado!","og_description":"Concurso UFPB: edital ofertou 116 vagas para o cargo de T\u00e9cnico-Administrativo em Educa\u00e7\u00e3o. Homologado o resultado!","og_url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-ufpb\/","og_site_name":"Estrat\u00e9gia Concursos","article_author":"https:\/\/www.facebook.com\/EstrategiaConcursos","article_published_time":"2025-04-24T09:20:00+00:00","article_modified_time":"2025-12-12T16:30:34+00:00","og_image":[{"width":768,"height":432,"url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/09\/27151749\/ufpb.jpg","type":"image\/jpeg"}],"author":"Coordena\u00e7\u00e3o","twitter_card":"summary_large_image","twitter_creator":"@EstratConcursos","twitter_site":"@EstratConcursos","twitter_misc":{"Escrito por":"Coordena\u00e7\u00e3o","Est. tempo de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-ufpb\/#article","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-ufpb\/"},"author":{"name":"Coordena\u00e7\u00e3o","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/b4a388c97673c5f483d72185668afa1f"},"headline":"Concurso UFPB: resultado final homologado!","datePublished":"2025-04-24T09:20:00+00:00","dateModified":"2025-12-12T16:30:34+00:00","mainEntityOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-ufpb\/"},"wordCount":1767,"commentCount":0,"publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-ufpb\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/09\/27151749\/ufpb.jpg","articleSection":["Educa\u00e7\u00e3o"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-ufpb\/#respond"]}],"copyrightYear":"2025","copyrightHolder":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-ufpb\/","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-ufpb\/","name":"Concurso UFPB: resultado final homologado!","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-ufpb\/#primaryimage"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-ufpb\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/09\/27151749\/ufpb.jpg","datePublished":"2025-04-24T09:20:00+00:00","dateModified":"2025-12-12T16:30:34+00:00","description":"Concurso UFPB: edital ofertou 116 vagas para o cargo de T\u00e9cnico-Administrativo em Educa\u00e7\u00e3o. Homologado o resultado!","breadcrumb":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-ufpb\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-ufpb\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-ufpb\/#primaryimage","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/09\/27151749\/ufpb.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/09\/27151749\/ufpb.jpg","width":768,"height":432},{"@type":"BreadcrumbList","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-ufpb\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.estrategiaconcursos.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Concurso UFPB: resultado final homologado!"}]},{"@type":"WebSite","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","name":"Estrat\u00e9gia Concursos","description":"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.","publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization","name":"Estrat\u00e9gia Concursos","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","width":230,"height":60,"caption":"Estrat\u00e9gia Concursos"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/EstratConcursos"]},{"@type":"Person","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/b4a388c97673c5f483d72185668afa1f","name":"Coordena\u00e7\u00e3o","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/b720319e4c9a967eb58678d110f4fe35452fc5d5f97b202bac7b8acceb18c6ad?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b720319e4c9a967eb58678d110f4fe35452fc5d5f97b202bac7b8acceb18c6ad?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b720319e4c9a967eb58678d110f4fe35452fc5d5f97b202bac7b8acceb18c6ad?s=96&d=mm&r=g","caption":"Coordena\u00e7\u00e3o"},"sameAs":["https:\/\/www.facebook.com\/EstrategiaConcursos","https:\/\/x.com\/EstratConcursos"],"url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/estrategia2013\/"}]}},"_links":{"self":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/739452","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/comments?post=739452"}],"version-history":[{"count":106,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/739452\/revisions"}],"predecessor-version":[{"id":1684555,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/739452\/revisions\/1684555"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media\/1467920"}],"wp:attachment":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media?parent=739452"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/categories?post=739452"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tags?post=739452"},{"taxonomy":"tax_estado","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tax_estado?post=739452"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}