{"id":717421,"date":"2021-04-19T22:56:21","date_gmt":"2021-04-20T01:56:21","guid":{"rendered":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?p=717421"},"modified":"2021-04-20T11:00:36","modified_gmt":"2021-04-20T14:00:36","slug":"informativo-stf-1012-comentado","status":"publish","type":"post","link":"https:\/\/www.estrategiaconcursos.com.br\/blog\/informativo-stf-1012-comentado\/","title":{"rendered":"Informativo STF 1012 Comentado"},"content":{"rendered":"\n<p>Informativo n\u00ba 1012 do STF <strong>COMENTADO<\/strong> pintando na telinha (do seu computador, notebook, tablet, celular&#8230;) para quem est\u00e1 ligado aqui conosco no Estrat\u00e9gia Carreiras Jur\u00eddicas!<\/p>\n\n\n\n<p class=\"has-text-align-center\"><strong><a href=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/04\/19225554\/stf-1012-1.pdf\">DOWNLOAD do PDF AQUI!<\/a><\/strong><\/p>\n\n\n<figure class=\"wp-block-embed-youtube wp-block-embed is-type-video is-provider-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"lyte-wrapper\" style=\"width:853px;max-width:100%;margin:5px;\"><div class=\"lyMe\" id=\"WYL_uuKxNVw50Hc\"><div id=\"lyte_uuKxNVw50Hc\" data-src=\"\/\/i.ytimg.com\/vi\/uuKxNVw50Hc\/hqdefault.jpg\" class=\"pL\"><div class=\"tC\"><div class=\"tT\"><\/div><\/div><div class=\"play\"><\/div><div class=\"ctrl\"><div class=\"Lctrl\"><\/div><div class=\"Rctrl\"><\/div><\/div><\/div><noscript><a href=\"https:\/\/youtu.be\/uuKxNVw50Hc\" rel=\"nofollow\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i.ytimg.com\/vi\/uuKxNVw50Hc\/0.jpg\" alt=\"YouTube video thumbnail\" width=\"853\" height=\"460\" \/><br \/>Assista a este v\u00eddeo no YouTube<\/a><\/noscript><\/div><\/div><div class=\"lL\" style=\"max-width:100%;width:853px;margin:5px;\"><\/div><figcaption><\/figcaption><\/figure>\n\n\n<p>Sum\u00e1rio<\/p>\n\n\n\n<p><a href=\"#_Toc69757819\">DIREITO ADMINISTRATIVO&#8230; 2<\/a><\/p>\n\n\n\n<p><a href=\"#_Toc69757820\">1.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Concession\u00e1rias de energia el\u00e9trica e utiliza\u00e7\u00e3o onerosa de faixas de dom\u00ednio p\u00fablico estadual 2<\/a><\/p>\n\n\n\n<p><a href=\"#_Toc69757821\">1.1.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Situa\u00e7\u00e3o F\u00c1TICA. 3<\/a><\/p>\n\n\n\n<p><a href=\"#_Toc69757822\">1.2.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; An\u00e1lise ESTRAT\u00c9GICA. 3<\/a><\/p>\n\n\n\n<p><a href=\"#_Toc69757823\">2.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Inconstitucionalidade material por viola\u00e7\u00e3o \u00e0 isonomia na rela\u00e7\u00e3o Estado-cidad\u00e3o.. 4<\/a><\/p>\n\n\n\n<p><a href=\"#_Toc69757824\">2.1.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Situa\u00e7\u00e3o F\u00c1TICA. 4<\/a><\/p>\n\n\n\n<p><a href=\"#_Toc69757825\">2.2.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; An\u00e1lise ESTRAT\u00c9GICA. 5<\/a><\/p>\n\n\n\n<p><a href=\"#_Toc69757826\">DIREITO CONSTITUCIONAL. 6<\/a><\/p>\n\n\n\n<p><a href=\"#_Toc69757827\">3.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Covid-19: Suspens\u00e3o do fornecimento de energia el\u00e9trica por falta de pagamento.. 6<\/a><\/p>\n\n\n\n<p><a href=\"#_Toc69757828\">3.1.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Situa\u00e7\u00e3o F\u00c1TICA. 6<\/a><\/p>\n\n\n\n<p><a href=\"#_Toc69757829\">3.2.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; An\u00e1lise ESTRAT\u00c9GICA. 7<\/a><\/p>\n\n\n\n<p><a href=\"#_Toc69757830\">4.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Covid-19: medidas de conten\u00e7\u00e3o \u00e0 transmiss\u00e3o do novo coronav\u00edrus e proibi\u00e7\u00e3o tempor\u00e1ria de atividades religiosas em ambiente presencial 8<\/a><\/p>\n\n\n\n<p><a href=\"#_Toc69757831\">4.1.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Situa\u00e7\u00e3o F\u00c1TICA. 9<\/a><\/p>\n\n\n\n<p><a href=\"#_Toc69757832\">4.2.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; An\u00e1lise ESTRAT\u00c9GICA. 9<\/a><\/p>\n\n\n\n<p><a href=\"#_Toc69757833\">5.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; DL 70\/1966 e recep\u00e7\u00e3o pela Constitui\u00e7\u00e3o Federal de 1988. 11<\/a><\/p>\n\n\n\n<p><a href=\"#_Toc69757834\">5.1.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Situa\u00e7\u00e3o F\u00c1TICA. 11<\/a><\/p>\n\n\n\n<p><a href=\"#_Toc69757835\">5.2.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; An\u00e1lise ESTRAT\u00c9GICA. 11<\/a><\/p>\n\n\n\n<p><a href=\"#_Toc69757836\">6.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Laicidade estatal e obrigatoriedade de manuten\u00e7\u00e3o de B\u00edblias em escolas e bibliotecas p\u00fablicas. 12<\/a><\/p>\n\n\n\n<p><a href=\"#_Toc69757837\">6.1.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Situa\u00e7\u00e3o F\u00c1TICA. 12<\/a><\/p>\n\n\n\n<p><a href=\"#_Toc69757838\">6.2.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; An\u00e1lise ESTRAT\u00c9GICA. 12<\/a><\/p>\n\n\n\n<p><a href=\"#_Toc69757839\">DIREITO CONSTITUCIONAL E TRIBUT\u00c1RIO&#8230; 13<\/a><\/p>\n\n\n\n<p><a href=\"#_Toc69757840\">7.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Imunidade tribut\u00e1ria: opera\u00e7\u00f5es financeiras e IOF. 13<\/a><\/p>\n\n\n\n<p><a href=\"#_Toc69757841\">7.1.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Situa\u00e7\u00e3o F\u00c1TICA. 14<\/a><\/p>\n\n\n\n<p><a href=\"#_Toc69757842\">7.2.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; An\u00e1lise ESTRAT\u00c9GICA. 14<\/a><\/p>\n\n\n\n<p><a href=\"#_Toc69757843\">8.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Contribui\u00e7\u00e3o ao Incra: natureza jur\u00eddica, folha de sal\u00e1rios e EC 33\/2001. 16<\/a><\/p>\n\n\n\n<p><a href=\"#_Toc69757844\">8.1.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Situa\u00e7\u00e3o F\u00c1TICA. 16<\/a><\/p>\n\n\n\n<p><a href=\"#_Toc69757845\">8.2.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; An\u00e1lise ESTRAT\u00c9GICA. 16<\/a><\/p>\n\n\n\n<p><a href=\"#_Toc69757846\">DIREITO CONSTITUCIONAL E DA SA\u00daDE.. 19<\/a><\/p>\n\n\n\n<p><a href=\"#_Toc69757847\">9.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Covid-19: leitos de UTI e custeio e financiamento pela Uni\u00e3o&nbsp;&nbsp; 19<\/a><\/p>\n\n\n\n<p><a href=\"#_Toc69757848\">9.1.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Situa\u00e7\u00e3o F\u00c1TICA. 19<\/a><\/p>\n\n\n\n<p><a href=\"#_Toc69757849\">9.2.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; An\u00e1lise ESTRAT\u00c9GICA. 19<\/a><\/p>\n\n\n\n<p><a href=\"#_Toc69757850\">DIREITO PROCESSUAL CIVIL. 21<\/a><\/p>\n\n\n\n<p><a href=\"#_Toc69757851\">10.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Limite territorial dos efeitos das decis\u00f5es em a\u00e7\u00e3o civil p\u00fablica: art. 16 da Lei 7.347\/1985. 21<\/a><\/p>\n\n\n\n<p><a href=\"#_Toc69757852\">10.1.&nbsp;&nbsp;&nbsp;&nbsp; Situa\u00e7\u00e3o F\u00c1TICA. 21<\/a><\/p>\n\n\n\n<p><a href=\"#_Toc69757853\">10.2.&nbsp;&nbsp;&nbsp;&nbsp; An\u00e1lise ESTRAT\u00c9GICA. 22<\/a><\/p>\n\n\n\n<p><a href=\"#_Toc69757854\">DIREITO PROCESSUAL PENAL. 23<\/a><\/p>\n\n\n\n<p><a href=\"#_Toc69757855\">11.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Atua\u00e7\u00e3o do juiz e ordem de inquiri\u00e7\u00e3o de testemunhas. 24<\/a><\/p>\n\n\n\n<p><a href=\"#_Toc69757856\">11.1.&nbsp;&nbsp;&nbsp;&nbsp; Situa\u00e7\u00e3o F\u00c1TICA. 24<\/a><\/p>\n\n\n\n<p><a href=\"#_Toc69757857\">11.2.&nbsp;&nbsp;&nbsp;&nbsp; An\u00e1lise ESTRAT\u00c9GICA. 24<\/a><\/p>\n\n\n\n\n\n<h1 class=\"wp-block-heading\" id=\"h-direito-administrativo\"><a>DIREITO ADMINISTRATIVO<\/a><\/h1>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-1-concession-rias-de-energia-el-trica-e-utiliza-o-onerosa-de-faixas-de-dom-nio-p-blico-estadual\"><a>1.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Concession\u00e1rias de energia el\u00e9trica e utiliza\u00e7\u00e3o onerosa de faixas de dom\u00ednio p\u00fablico estadual<\/a><\/h2>\n\n\n\n<p><strong>A\u00c7\u00c3O DIRETA DE INCONSTITUCIONALIDADE<\/strong><\/p>\n\n\n\n<p>\u00c9 inconstitucional norma estadual que onere contrato de concess\u00e3o de energia el\u00e9trica pela utiliza\u00e7\u00e3o de faixas de dom\u00ednio p\u00fablico adjacentes a rodovias estaduais ou federais.<\/p>\n\n\n\n<p>ADI 3763\/RS, relatora Min. C\u00e1rmen L\u00facia, julgamento virtual finalizado em 7.4.2021(Info 1012)<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-1-1-situa-o-f-tica\"><a>1.1. Situa\u00e7\u00e3o F\u00c1TICA.<\/a><\/h3>\n\n\n\n<p>A Associa\u00e7\u00e3o Brasileira de Distribuidores de Energia El\u00e9trica (Abradee) ajuizou a A\u00e7\u00e3o Direta de Inconstitucionalidade (ADI) 3763, com pedido de liminar, no Supremo Tribunal Federal (STF). Os advogados da associa\u00e7\u00e3o querem anular os efeitos de uma lei e de um decreto ga\u00fachos que permitem, ao governo do Estado, explorar comercialmente \u00e1reas lim\u00edtrofes \u00e0s rodovias estaduais e federais.<\/p>\n\n\n\n<p>A Lei Estadual 12.238, de 14 de janeiro de 2005, que a Abradee impugna, garantiu ao governo do Rio Grande do Sul a \u201cexplora\u00e7\u00e3o da utiliza\u00e7\u00e3o e comercializa\u00e7\u00e3o, a t\u00edtulo oneroso, das faixas de dom\u00ednio e das \u00e1reas adjacentes \u00e0s rodovias estaduais e federais delegadas ao Estado\u201d. Posteriormente, o Decreto 43.787, de 12 de maio de 2005, regulamentou a lei ga\u00facha, com a previs\u00e3o de cobran\u00e7a de remunera\u00e7\u00e3o e multas a serem pagas pelas concession\u00e1rias.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-1-2-an-lise-estrat-gica\"><a>1.2. An\u00e1lise ESTRAT\u00c9GICA.<\/a><\/h3>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-1-2-1-quest-o-jur-dica\">1.2.1.&nbsp; Quest\u00e3o JUR\u00cdDICA.<\/h4>\n\n\n\n<p>Constitui\u00e7\u00e3o Federal:<\/p>\n\n\n\n<p>Art. 21. Compete \u00e0 Uni\u00e3o:<\/p>\n\n\n\n<p>XII &#8211; explorar, diretamente ou mediante autoriza\u00e7\u00e3o, concess\u00e3o ou permiss\u00e3o:<\/p>\n\n\n\n<p>b) os servi\u00e7os e instala\u00e7\u00f5es de energia el\u00e9trica e o aproveitamento energ\u00e9tico dos cursos de \u00e1gua, em articula\u00e7\u00e3o com os Estados onde se situam os potenciais hidroenerg\u00e9ticos;<\/p>\n\n\n\n<p>Art. 22. Compete privativamente \u00e0 Uni\u00e3o legislar sobre:<\/p>\n\n\n\n<p>IV &#8211; \u00e1guas, energia, inform\u00e1tica, telecomunica\u00e7\u00f5es e radiodifus\u00e3o;<\/p>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-1-2-2-a-norma-estadual-encontra-amparo-na-cf\">1.2.2.&nbsp;&nbsp;&nbsp;&nbsp; A norma estadual encontra amparo na CF?<\/h4>\n\n\n\n<p><strong><em><u>R:<\/u><\/em><\/strong> <strong>Negativo.<\/strong><\/p>\n\n\n\n<p>Isso porque a Uni\u00e3o, por ser titular da presta\u00e7\u00e3o do servi\u00e7o p\u00fablico de energia el\u00e9trica (arts. 21, XII, b, e 22, IV, da Constitui\u00e7\u00e3o Federal), det\u00e9m a prerrogativa constitucional de estabelecer o regime e as condi\u00e7\u00f5es da presta\u00e7\u00e3o desse servi\u00e7o por concession\u00e1rias, o qual n\u00e3o pode sofrer inger\u00eancia normativa dos demais entes pol\u00edticos.<\/p>\n\n\n\n<p>Ademais, na linha da jurisprud\u00eancia do Supremo Tribunal Federal, n\u00e3o h\u00e1 possibilidade de interfer\u00eancia do estado-membro nas rela\u00e7\u00f5es jur\u00eddico-contratuais entre Poder concedente federal e as empresas concession\u00e1rias, especificamente no que tange a altera\u00e7\u00f5es das condi\u00e7\u00f5es estipuladas em contrato de concess\u00e3o de servi\u00e7os p\u00fablicos, sob regime federal, mediante edi\u00e7\u00e3o de leis estaduais.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-1-2-3-resultado-final\">1.2.3.&nbsp; Resultado final.<\/h4>\n\n\n\n<p>Com base nesse entendimento, o Plen\u00e1rio, por maioria, julgou parcialmente procedente o pedido formulado na a\u00e7\u00e3o direta para: a) atribuir interpreta\u00e7\u00e3o conforme a Constitui\u00e7\u00e3o \u00e0 Lei 12.238\/2005 e ao Decreto regulamentar 43.787\/2005 do estado do Rio Grande do Sul, excluindo da incid\u00eancia de ambos os diplomas as concession\u00e1rias de servi\u00e7o p\u00fablico de energia el\u00e9trica; e b) declarar a inconstitucionalidade da express\u00e3o \u201cde energia\u201d, contida no inciso IV do art. 6\u00ba, e da Tarifa B\u00e1sica prevista no Tipo II do Item 1 do Anexo I do mencionado Decreto.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-2-inconstitucionalidade-material-por-viola-o-isonomia-na-rela-o-estado-cidad-o\"><a>2.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Inconstitucionalidade material por viola\u00e7\u00e3o \u00e0 isonomia na rela\u00e7\u00e3o Estado-cidad\u00e3o<\/a><\/h2>\n\n\n\n<p><strong>A\u00c7\u00c3O DIRETA DE INCONSTITUCIONALIDADE<\/strong><\/p>\n\n\n\n<p>\u00c9 inconstitucional lei estadual que estabele\u00e7a prazo decadencial de 10 (dez) anos para anula\u00e7\u00e3o de atos administrativos reputados inv\u00e1lidos pela Administra\u00e7\u00e3o P\u00fablica estadual.<\/p>\n\n\n\n<p>ADI 6019\/SP, relator Min. Marco Aur\u00e9lio, redator do ac\u00f3rd\u00e3o Min. Roberto Barroso, julgamento virtual finalizado em 12.4.2021(Info 1012)<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-2-1-situa-o-f-tica\"><a>2.1. Situa\u00e7\u00e3o F\u00c1TICA.<\/a><\/h3>\n\n\n\n<p>A Associa\u00e7\u00e3o Brasileira de Concession\u00e1rias de Rodovias (ABCR) ajuizou a A\u00e7\u00e3o Direta de Inconstitucionalidade (ADI) 6019, no Supremo Tribunal Federal (STF), contra dispositivo da Lei 10.177\/1998, do Estado de S\u00e3o Paulo, que prev\u00ea o prazo de 10 anos para que a administra\u00e7\u00e3o p\u00fablica paulista anule atos reputados como inv\u00e1lidos. Na a\u00e7\u00e3o, a entidade argumenta que a norma invade compet\u00eancia legislativa privativa da Uni\u00e3o por disciplinar tema de Direito Civil (decad\u00eancia).<\/p>\n\n\n\n<p>O artigo 10 da Lei 10.177\/1998 disp\u00f5e que \u201ca administra\u00e7\u00e3o p\u00fablica anular\u00e1 seus atos inv\u00e1lidos, de of\u00edcio ou por provoca\u00e7\u00e3o de pessoa interessada, salvo quando ultrapassado o prazo de dez anos contado de sua produ\u00e7\u00e3o\u201d. Para a ABCR, o prazo decadencial de 10 anos previsto na lei paulista n\u00e3o se harmoniza com os preceitos constitucionais da seguran\u00e7a jur\u00eddica, da razoabilidade, da isonomia e da proporcionalidade.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-2-2-an-lise-estrat-gica\"><a>2.2. An\u00e1lise ESTRAT\u00c9GICA.<\/a><\/h3>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-2-2-1-quest-o-jur-dica\">2.2.1.&nbsp; Quest\u00e3o JUR\u00cdDICA.<\/h4>\n\n\n\n<p>Lei 9.784\/1999:<\/p>\n\n\n\n<p>Art. 54. O direito da Administra\u00e7\u00e3o de anular os atos administrativos de que decorram efeitos favor\u00e1veis para os destinat\u00e1rios decai em cinco anos, contados da data em que foram praticados, salvo comprovada m\u00e1-f\u00e9.<\/p>\n\n\n\n<p>\u00a7 1\u00ba No caso de efeitos patrimoniais cont\u00ednuos, o prazo de decad\u00eancia contar-se-\u00e1 da percep\u00e7\u00e3o do primeiro pagamento.<\/p>\n\n\n\n<p>\u00a7 2\u00ba Considera-se exerc\u00edcio do direito de anular qualquer medida de autoridade administrativa que importe impugna\u00e7\u00e3o \u00e0 validade do ato.<\/p>\n\n\n\n<p>Lei 10.177\/1998:<\/p>\n\n\n\n<p>Artigo 10 &#8211; A Administra\u00e7\u00e3o P\u00fablica anular\u00e1 seus atos inv\u00e1lidos, de of\u00edcio ou por provoca\u00e7\u00e3o de pessoa interessada, salvo quando:<\/p>\n\n\n\n<p>I &#8211; ultrapassado o prazo de dez anos contado de sua produ\u00e7\u00e3o;<\/p>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-2-2-2-t-valendo-ampliar-o-prazo-decadencial\">2.2.2.&nbsp;&nbsp;&nbsp;&nbsp; T\u00e1 valendo ampliar o prazo decadencial?<\/h4>\n\n\n\n<p><strong><em><u>R:<\/u><\/em><\/strong> <strong>Nops!<\/strong><\/p>\n\n\n\n<p>O prazo quinquenal consolidou-se como MARCO TEMPORAL geral nas rela\u00e7\u00f5es entre o Poder P\u00fablico e particulares e o STF <strong>somente admite exce\u00e7\u00f5es ao princ\u00edpio da isonomia quando houver fundamento razo\u00e1vel<\/strong> baseado na necessidade de remediar um desequil\u00edbrio espec\u00edfico entre as partes.<\/p>\n\n\n\n<p>Se os demais estados da Federa\u00e7\u00e3o aplicam, indistintamente, o prazo quinquenal para anula\u00e7\u00e3o de atos administrativos de que decorram efeitos favor\u00e1veis aos administrados, seja por previs\u00e3o em lei pr\u00f3pria ou por aplica\u00e7\u00e3o anal\u00f3gica do art. 54 da Lei 9.784\/1999, N\u00c3O h\u00e1 fundamento constitucional que justifique a situa\u00e7\u00e3o excepcional de um determinado estado-membro. Logo, imp\u00f5e-se o tratamento IGUALIT\u00c1RIO nas rela\u00e7\u00f5es Estado-cidad\u00e3o.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-2-2-3-resultado-final\">2.2.3.&nbsp; Resultado final.<\/h4>\n\n\n\n<p>Com base nesse entendimento, o Plen\u00e1rio, por maioria, julgou procedente o pedido formulado em a\u00e7\u00e3o direta para declarar a inconstitucionalidade do art. 10, I, da Lei 10.177\/1998 do estado de S\u00e3o Paulo. Vencidos os ministros Alexandre de Moraes, Ricardo Lewandowski, Dias Toffoli que, preliminarmente, n\u00e3o conheceram da a\u00e7\u00e3o e, no m\u00e9rito, julgaram improcedente o pedido. O ministro Marco Aur\u00e9lio (relator) tamb\u00e9m julgou o pedido procedente, mas ficou parcialmente vencido por declarar a inconstitucionalidade do dispositivo ante a exist\u00eancia de v\u00edcios formal e material.<\/p>\n\n\n\n<h1 class=\"wp-block-heading\" id=\"h-direito-constitucional\"><a>DIREITO CONSTITUCIONAL<\/a><\/h1>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-3-covid-19-suspens-o-do-fornecimento-de-energia-el-trica-por-falta-de-pagamento\"><a>3.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Covid-19: Suspens\u00e3o do fornecimento de energia el\u00e9trica por falta de pagamento<\/a><\/h2>\n\n\n\n<p><strong>A\u00c7\u00c3O DIRETA DE INCONSTITUCIONALIDADE<\/strong><\/p>\n\n\n\n<p>S\u00e3o constitucionais as normas estaduais, editadas em raz\u00e3o da pandemia causada pelo novo coronav\u00edrus, pelas quais veiculados a proibi\u00e7\u00e3o de suspens\u00e3o do fornecimento do servi\u00e7o de energia el\u00e9trica, o modo de cobran\u00e7a, a forma de pagamentos dos d\u00e9bitos e a exigibilidade de multa e juros morat\u00f3rios.<\/p>\n\n\n\n<p>ADI 6432\/RR, relatora Min. C\u00e1rmen L\u00facia, julgamento virtual finalizado em 7.4.2021 (Info 1012)<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-3-1-situa-o-f-tica\"><a>3.1. Situa\u00e7\u00e3o F\u00c1TICA.<\/a><\/h3>\n\n\n\n<p>A Associa\u00e7\u00e3o Brasileira de Distribuidores de Energia El\u00e9trica (Abradee) ajuizou no Supremo Tribunal Federal (STF) a A\u00e7\u00e3o Direta de Inconstitucionalidade (ADI) 6432, contra dispositivos da Lei estadual 1.389\/2020 de Roraima, que pro\u00edbe o corte de energia el\u00e9trica em resid\u00eancias por inadimpl\u00eancia enquanto perdurar o estado de emerg\u00eancia no estado, devido \u00e0 pandemia da Covid-19.<\/p>\n\n\n\n<p>&nbsp;A norma suspende ainda a incid\u00eancia de multas e juros por atraso de pagamento da fatura durante o per\u00edodo. Determina tamb\u00e9m que as concession\u00e1rias, antes de interromper o servi\u00e7o em raz\u00e3o da inadimpl\u00eancia anterior a mar\u00e7o de 2020, dever\u00e3o possibilitar o parcelamento do d\u00e9bito das faturas referentes ao per\u00edodo de conting\u00eancia.<\/p>\n\n\n\n<p>&nbsp;Segundo a Abradee, a compet\u00eancia privativa para legislar sobre energia el\u00e9trica \u00e9 da Uni\u00e3o, a quem compete tamb\u00e9m planejar e promover a defesa permanente contra as calamidades p\u00fablicas. A associa\u00e7\u00e3o argumenta que resolu\u00e7\u00e3o da Ag\u00eancia Nacional de Energia El\u00e9trica (Aneel) trata das regras de suspens\u00e3o de fornecimento, modo de cobran\u00e7a e pagamento dos d\u00e9bitos apurados e hip\u00f3teses de multa e juros por atraso durante a pandemia. Aponta, ainda, que a Medida Provis\u00f3ria 950\/2020 j\u00e1 prev\u00ea a isen\u00e7\u00e3o do pagamento da fatura, por tr\u00eas meses, para os benefici\u00e1rios da tarifa social com consumo de at\u00e9 220 kWh.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-3-2-an-lise-estrat-gica\"><a>3.2. An\u00e1lise ESTRAT\u00c9GICA.<\/a><\/h3>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-3-2-1-quest-o-jur-dica\">3.2.1.&nbsp; Quest\u00e3o JUR\u00cdDICA.<\/h4>\n\n\n\n<p>Constitui\u00e7\u00e3o Federal:<\/p>\n\n\n\n<p>Art. 21. Compete \u00e0 Uni\u00e3o:<\/p>\n\n\n\n<p>XII &#8211; explorar, diretamente ou mediante autoriza\u00e7\u00e3o, concess\u00e3o ou permiss\u00e3o:<\/p>\n\n\n\n<p>b) os servi\u00e7os e instala\u00e7\u00f5es de energia el\u00e9trica e o aproveitamento energ\u00e9tico dos cursos de \u00e1gua, em articula\u00e7\u00e3o com os Estados onde se situam os potenciais hidroenerg\u00e9ticos;<\/p>\n\n\n\n<p>Art. 22. Compete privativamente \u00e0 Uni\u00e3o legislar sobre:<\/p>\n\n\n\n<p>IV &#8211; \u00e1guas, energia, inform\u00e1tica, telecomunica\u00e7\u00f5es e radiodifus\u00e3o;<\/p>\n\n\n\n<p>Art. 24. Compete \u00e0 Uni\u00e3o, aos Estados e ao Distrito Federal legislar concorrentemente sobre:<\/p>\n\n\n\n<p>V &#8211; produ\u00e7\u00e3o e consumo;<\/p>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-3-2-2-cortar-a-luz-dos-inadimplentes\">3.2.2.&nbsp;&nbsp;&nbsp;&nbsp; \u201cCortar a luz\u201d dos inadimplentes?<\/h4>\n\n\n\n<p><strong><em><u>R:<\/u><\/em><\/strong> <strong>Fa\u00e7a-se a Luz!<\/strong><\/p>\n\n\n\n<p>As normas objetivam regulamentar a rela\u00e7\u00e3o entre o usu\u00e1rio do servi\u00e7o e a empresa concession\u00e1ria, tratando-se, portanto, essencialmente de normas sobre defesa e prote\u00e7\u00e3o dos direitos do consumidor e da sa\u00fade p\u00fablica.<\/p>\n\n\n\n<p>N\u00e3o h\u00e1 se falar em invas\u00e3o da compet\u00eancia legislativa privativa da Uni\u00e3o para legislar sobre energia el\u00e9trica, pois a legisla\u00e7\u00e3o estadual impugnada n\u00e3o atinge de forma direta a rela\u00e7\u00e3o contratual estabelecida entre a concession\u00e1ria e o Poder P\u00fablico concedente, titular do servi\u00e7o. Tampouco fere o n\u00facleo de atua\u00e7\u00e3o das empresas voltadas \u00e0 presta\u00e7\u00e3o de servi\u00e7os de fornecimento de energia el\u00e9trica, uma vez que n\u00e3o se constata possa gerar desequil\u00edbrio contratual ou afetar pol\u00edticas tarif\u00e1rias, especialmente porque as medidas impostas s\u00e3o excepcionais e transit\u00f3rias, limitadas ao tempo da vig\u00eancia do plano de conting\u00eancia adotado pela Secretaria estadual de sa\u00fade em decorr\u00eancia da pandemia de Covid-19.<\/p>\n\n\n\n<p>Por outro lado, a n\u00e3o interrup\u00e7\u00e3o dos servi\u00e7os p\u00fablicos de energia el\u00e9trica relaciona-se \u00e0 satisfa\u00e7\u00e3o das necessidades B\u00c1SICAS da popula\u00e7\u00e3o, pelo que a continuidade do servi\u00e7o \u00e9 considerada ESSENCIAL para a ado\u00e7\u00e3o de medidas de conten\u00e7\u00e3o do novo coronav\u00edrus.<\/p>\n\n\n\n<p>O fornecimento de energia el\u00e9trica \u00e9 direito fundamental relacionado \u00e0 dignidade humana, ao direito \u00e0 sa\u00fade, \u00e0 moradia, \u00e0 alimenta\u00e7\u00e3o, \u00e0 educa\u00e7\u00e3o e \u00e0 profiss\u00e3o, constituindo-se em servi\u00e7o p\u00fablico essencial e universal, que deve estar dispon\u00edvel a todos os cidad\u00e3os, especialmente no complexo contexto pand\u00eamico vivenciado.<\/p>\n\n\n\n<p>\u00c9 de se ressaltar que a superveni\u00eancia de Lei federal 14.015\/2020, pela qual se disp\u00f5e sobre interrup\u00e7\u00e3o, religa\u00e7\u00e3o ou restabelecimento de servi\u00e7os p\u00fablicos, tamb\u00e9m editada em raz\u00e3o da pandemia de Covid-19, n\u00e3o afasta a compet\u00eancia estadual para disciplinar a mat\u00e9ria de prote\u00e7\u00e3o e defesa do consumidor de forma mais ampla do que a estabelecida pela legisla\u00e7\u00e3o federal, como assentado em recentes decis\u00f5es do Supremo Tribunal Federal.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-3-2-3-resultado-final\">3.2.3.&nbsp; Resultado final.<\/h4>\n\n\n\n<p>Com base nesse entendimento, o Plen\u00e1rio, por maioria, julgou improcedente o pedido formulado na a\u00e7\u00e3o direta para declarar constitucionais as normas previstas no \u00a7 1\u00ba do art. 2\u00ba, no \u00a7 2\u00ba do art. 2\u00ba e nos arts. 3\u00ba, 4\u00ba, 5\u00ba e 6\u00ba da Lei 1.389\/2020 do estado de Roraima, na parte afeta \u00e0 \u201cenergia el\u00e9trica\u201d. Vencidos os ministros Dias Toffoli, Luiz Fux (presidente), Nunes Marques e Gilmar Mendes.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-4-covid-19-medidas-de-conten-o-transmiss-o-do-novo-coronav-rus-e-proibi-o-tempor-ria-de-atividades-religiosas-em-ambiente-presencial\"><a>4.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Covid-19: medidas de conten\u00e7\u00e3o \u00e0 transmiss\u00e3o do novo coronav\u00edrus e proibi\u00e7\u00e3o tempor\u00e1ria de atividades religiosas em ambiente presencial<\/a><\/h2>\n\n\n\n<p><strong>A\u00c7\u00c3O DE DESCUMPRIMENTO DE PRECEITO FUNDAMENTAL<\/strong><\/p>\n\n\n\n<p>\u00c9 compat\u00edvel com a Constitui\u00e7\u00e3o Federal a imposi\u00e7\u00e3o de restri\u00e7\u00f5es \u00e0 realiza\u00e7\u00e3o de cultos, missas e demais atividades religiosas presenciais de car\u00e1ter coletivo como medida de conten\u00e7\u00e3o do avan\u00e7o da pandemia da Covid-19.<\/p>\n\n\n\n<p>ADPF 811\/SP, relator Min. Gilmar Mendes, julgamento em 8.4.2021(Info 1012)<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-4-1-situa-o-f-tica\"><a>4.1. Situa\u00e7\u00e3o F\u00c1TICA.<\/a><\/h3>\n\n\n\n<p>Trata-se de argui\u00e7\u00e3o de descumprimento de preceito fundamental ajuizada contra o Decreto 65.563\/2021 do estado de S\u00e3o Paulo que limitou a realiza\u00e7\u00e3o de cultos, missas e demais atividades religiosas de car\u00e1ter coletivo, durante o per\u00edodo de agravamento da pandemia da Covid-19.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-4-2-an-lise-estrat-gica\"><a>4.2. An\u00e1lise ESTRAT\u00c9GICA.<\/a><\/h3>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-4-2-1-quest-o-jur-dica\">4.2.1.&nbsp; Quest\u00e3o JUR\u00cdDICA.<\/h4>\n\n\n\n<p>Decreto 65.563\/2021:<\/p>\n\n\n\n<p>Artigo 2\u00ba &#8211; As medidas emergenciais institu\u00eddas por este decreto consistem na veda\u00e7\u00e3o de:<\/p>\n\n\n\n<p>II &#8211; realiza\u00e7\u00e3o de:<\/p>\n\n\n\n<p>a) cultos, missas e demais atividades religiosas de car\u00e1ter coletivo;<\/p>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-4-2-2-os-entes-podem-proibir-a-realiza-o-dos-cultos-e-missas-de-car-ter-coletivo\">4.2.2.&nbsp;&nbsp;&nbsp;&nbsp; Os entes podem proibir a realiza\u00e7\u00e3o dos cultos e missas de car\u00e1ter coletivo?<\/h4>\n\n\n\n<p><strong><em><u>R:<\/u><\/em><\/strong> <strong>SIM!!!<\/strong><\/p>\n\n\n\n<p>A liberdade de cren\u00e7a e de culto, usualmente caracterizada apenas pela f\u00f3rmula gen\u00e9rica \u201cliberdade religiosa\u201d, constitui uma das primeiras garantias individuais albergadas pelas declara\u00e7\u00f5es de direitos do s\u00e9culo XVIII que alcan\u00e7aram a condi\u00e7\u00e3o de direito humano e fundamental.<\/p>\n\n\n\n<p><strong>A liberdade de realiza\u00e7\u00e3o de cultos coletivos, no entanto, n\u00e3o \u00e9 absoluta<\/strong>. A Constitui\u00e7\u00e3o Federal (CF), ao estabelecer inequ\u00edvoca reserva de lei ao exerc\u00edcio dos cultos religiosos, permite a restri\u00e7\u00e3o ao direito \u00e0 liberdade religiosa em sua \u201cdimens\u00e3o externa\u201d, que compreende a liberdade de cren\u00e7a, a liberdade de aderir a alguma religi\u00e3o e a liberdade de exerc\u00edcio do culto respectivo. A lei deve proteger os templos e n\u00e3o deve interferir nas liturgias, a n\u00e3o ser que assim o imponha algum valor constitucional concorrente de maior peso.<\/p>\n\n\n\n<p>Sob o prisma da constitucionalidade formal, a imposi\u00e7\u00e3o de restri\u00e7\u00f5es \u00e0 realiza\u00e7\u00e3o de cultos religiosos por meio de decretos municipais e estaduais est\u00e1 em conformidade com decis\u00f5es recentes do STF sobre a tem\u00e1tica, dentre as quais destaca-se a ADI 6341, na qual assentou-se que todos os entes federados possuem compet\u00eancia para legislar e adotar medidas sanit\u00e1rias voltadas ao enfrentamento da emerg\u00eancia de sa\u00fade p\u00fablica.<\/p>\n\n\n\n<p>Nesse sentido, o STF reafirmou o dever que todos os entes pol\u00edticos t\u00eam na promo\u00e7\u00e3o da sa\u00fade p\u00fablica e, coerente ao federalismo cooperativo adotado na CF, assentou a compet\u00eancia dos estados e dos munic\u00edpios, ao lado da Uni\u00e3o, na ado\u00e7\u00e3o de medidas sanit\u00e1rias direcionadas ao enfrentamento da pandemia.<\/p>\n\n\n\n<p>Sob o aspecto material, a medida sanit\u00e1ria em an\u00e1lise mostra-se adequada, necess\u00e1ria e proporcional, bem como em conson\u00e2ncia com as diretrizes cient\u00edficas propostas pela Organiza\u00e7\u00e3o Mundial da Sa\u00fade.<\/p>\n\n\n\n<p>Ademais, \u00e9 poss\u00edvel afirmar que h\u00e1 um razo\u00e1vel consenso na comunidade cient\u00edfica no sentido de que os riscos de contamina\u00e7\u00e3o decorrentes de atividades religiosas coletivas s\u00e3o superiores aos riscos de outras atividades econ\u00f4micas, mesmo aquelas realizadas em ambientes fechados. Essa no\u00e7\u00e3o geral \u2014 sobre o elevado risco de contamina\u00e7\u00e3o das atividades religiosas coletivas presenciais \u2014 foi complementada por um exame de fatos e prognoses subjacente \u00e0 edi\u00e7\u00e3o do decreto estadual impugnado. As medidas restritivas, dessa forma, foram resultantes de an\u00e1lises t\u00e9cnicas relativas ao risco ambiental de cont\u00e1gio pela Covid-19 conforme o setor econ\u00f4mico e social, bem como de acordo com a necessidade de preservar a capacidade de atendimento da rede de servi\u00e7o de sa\u00fade p\u00fablica.<\/p>\n\n\n\n<p>Observa-se, por fim, que, no caso, o art. 2\u00ba da norma impugnada n\u00e3o se limitou a restringir as atividades religiosas coletivas (inciso II), mas tamb\u00e9m restringiu outras atividades econ\u00f4micas altamente essenciais, tais como o \u201catendimento presencial ao p\u00fablico, inclusive mediante retirada ou \u2018pegue e leve\u2019, em bares, restaurantes, \u2018shopping centers\u2019, galerias e estabelecimentos cong\u00eaneres e com\u00e9rcio varejista de materiais de constru\u00e7\u00e3o, permitidos t\u00e3o somente os servi\u00e7os de entrega (\u2018delivery\u2019) e \u2018drive-thru\u2019 (inciso I)\u201d e ainda \u201creuni\u00e3o, concentra\u00e7\u00e3o ou perman\u00eancia de pessoas nos espa\u00e7os p\u00fablicos, em especial, nas praias e parques\u201d.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-4-2-3-resultado-final\">4.2.3.&nbsp; Resultado final.<\/h4>\n\n\n\n<p>Com base nesse entendimento, o Plen\u00e1rio, por maioria, converteu o julgamento de medida cautelar em julgamento definitivo de m\u00e9rito e julgou improcedente o pedido formulado na a\u00e7\u00e3o. Vencidos os ministros Nunes Marques e Dias Toffoli, que julgaram o pedido procedente.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-5-dl-70-1966-e-recep-o-pela-constitui-o-federal-de-1988\"><a>5.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; DL 70\/1966 e recep\u00e7\u00e3o pela Constitui\u00e7\u00e3o Federal de 1988<\/a><\/h2>\n\n\n\n<p><strong>RECURSO EXTRAORDIN\u00c1RIO<\/strong><\/p>\n\n\n\n<p>\u00c9 constitucional, pois foi devidamente recepcionado pela Constitui\u00e7\u00e3o Federal de 1988, o procedimento de execu\u00e7\u00e3o extrajudicial (de d\u00edvidas hipotec\u00e1rias), previsto no Decreto-lei n\u00ba 70\/66.<\/p>\n\n\n\n<p>RE 556520\/SP, relator Min. Marco Aur\u00e9lio, redator do ac\u00f3rd\u00e3o Min. Dias Toffoli, julgamento virtual finalizado em 7.4.2021(Info 1012)<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-5-1-situa-o-f-tica\"><a>5.1. Situa\u00e7\u00e3o F\u00c1TICA.<\/a><\/h3>\n\n\n\n<p>Jo\u00e3o e Maria adquiriram um im\u00f3vel (a casa dos sonhos). O casalzinho e o banco adotaram, no contrato de compra e venda, o procedimento extrajudicial de cr\u00e9dito hipotec\u00e1rio. S\u00f3 que Maria perdeu o emprego e Jo\u00e3o n\u00e3o era muito dado ao trabalho. Acabaram caindo em inadimpl\u00eancia. O casal teve contra si promovida execu\u00e7\u00e3o extrajudicial do im\u00f3vel e esse foi arrematado pelo credor hipotec\u00e1rio.<\/p>\n\n\n\n<p>Ocorre que o Tribunal desfez a arremata\u00e7\u00e3o entendendo serem inconstitucionais os artigos 30, parte final, 31 a 38 do Decreto-lei 70\/1966, que disp\u00f5em sobre o procedimento da extrajudicial de d\u00edvidas hipotec\u00e1rias.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-5-2-an-lise-estrat-gica\"><a>5.2. An\u00e1lise ESTRAT\u00c9GICA.<\/a><\/h3>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-5-2-1-o-decreto-lei-70-1966-foi-recepcionado\">5.2.1.&nbsp;&nbsp;&nbsp;&nbsp; O Decreto-lei 70\/1966 foi recepcionado?<\/h4>\n\n\n\n<p><strong><em><u>R:<\/u><\/em><\/strong> <strong>SIM!<\/strong><\/p>\n\n\n\n<p>Na linha de diversos precedentes do Supremo Tribunal Federal (STF), a compatibilidade decorre da constata\u00e7\u00e3o de que esse procedimento n\u00e3o \u00e9 realizado de forma aleat\u00f3ria.<\/p>\n\n\n\n<p>Ele se submete a efetivo controle judicial, em ao menos uma de suas fases, sendo certo que o devedor \u00e9 intimado a acompanh\u00e1-lo, podendo impugnar, inclusive no \u00e2mbito judicial, o desenrolar do procedimento, se irregularidades vierem a ocorrer durante o seu tr\u00e2mite.<\/p>\n\n\n\n<p>Ali\u00e1s, a execu\u00e7\u00e3o extrajudicial de d\u00edvida hipotec\u00e1ria n\u00e3o \u00e9 uma inven\u00e7\u00e3o da cabe\u00e7a dos juristas brasileiros. Nem \u00e9 uma inova\u00e7\u00e3o do questionado decreto-lei, j\u00e1 que contemplada nos artigos 774, inciso IlI, do CC, e artigo 279, do C\u00f3digo Comercial, al\u00e9m do artigo 120, par\u00e1grafo 2\u00ba, da lei de fal\u00eancias.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-5-2-2-resultado-final\">5.2.2.&nbsp; Resultado final.<\/h4>\n\n\n\n<p>Com base nesse entendimento, o Plen\u00e1rio, por maioria, ao apreciar o Tema 249 da repercuss\u00e3o geral, negou provimento a recurso extraordin\u00e1rio. Seguindo a mesma orienta\u00e7\u00e3o, o Plen\u00e1rio, tamb\u00e9m por maioria, deu provimento a outro recurso extraordin\u00e1rio julgado em conjunto. Vencidos, em ambos os julgados, os ministros Luiz Fux (Presidente), C\u00e1rmen L\u00facia, Ayres Britto, Edson Fachin e Marco Aur\u00e9lio.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-6-laicidade-estatal-e-obrigatoriedade-de-manuten-o-de-b-blias-em-escolas-e-bibliotecas-p-blicas\"><a>6.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Laicidade estatal e obrigatoriedade de manuten\u00e7\u00e3o de B\u00edblias em escolas e bibliotecas p\u00fablicas<\/a><\/h2>\n\n\n\n<p><strong>A\u00c7\u00c3O DIRETA DE INCONSTITUCIONALIDADE<\/strong><\/p>\n\n\n\n<p>A imposi\u00e7\u00e3o legal de manuten\u00e7\u00e3o de exemplares de B\u00edblias em escolas e bibliotecas p\u00fablicas estaduais configura contrariedade \u00e0 laicidade estatal e \u00e0 liberdade religiosa consagrada pela Constitui\u00e7\u00e3o da Rep\u00fablica de 1988.<\/p>\n\n\n\n<p>ADI 5258\/AM, relatora Min. C\u00e1rmen L\u00facia, julgamento virtual finalizado em 12.4.2021(Info 1012)<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-6-1-situa-o-f-tica\"><a>6.1. Situa\u00e7\u00e3o F\u00c1TICA.<\/a><\/h3>\n\n\n\n<p>A Procuradoria-Geral da Rep\u00fablica (PGR) ajuizou A\u00e7\u00e3o Direta de Inconstitucionalidade (ADI) contra a norma do Amazonas que obriga as escolas e as bibliotecas p\u00fablicas estaduais a manterem em seu acervo ao menos um exemplar da B\u00edblia Sagrada para livre consulta.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-6-2-an-lise-estrat-gica\"><a>6.2. An\u00e1lise ESTRAT\u00c9GICA.<\/a><\/h3>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-6-2-1-quest-o-jur-dica\">6.2.1.&nbsp; Quest\u00e3o JUR\u00cdDICA.<\/h4>\n\n\n\n<p>Lei \u201cPromulgada\u201d 74\/2010 do estado do Amazonas:<\/p>\n\n\n\n<p>Art. 1\u00ba &#8211; As unidades escolares da rede estadual de ensino e as bibliotecas p\u00fablicas estaduais ficam obrigadas a manter em seus acervos ao menos um exemplar da B\u00edblia Sagrada. Par\u00e1grafo \u00fanico. A obrigatoriedade prevista no caput n\u00e3o implica em restri\u00e7\u00e3o ou impedimento para a manuten\u00e7\u00e3o, nos acervos p\u00fablicos, de livros sagrados de outras tradi\u00e7\u00f5es religiosas.<\/p>\n\n\n\n<p>Art. 2\u00ba &#8211; Os exemplares da B\u00edblia Sagrada dever\u00e3o ser colocados \u00e0 disposi\u00e7\u00e3o de alunos, professores e demais usu\u00e1rios, em local vis\u00edvel e de f\u00e1cil acesso.<\/p>\n\n\n\n<p>Art. 4\u00ba As despesas decorrentes da execu\u00e7\u00e3o desta lei correr\u00e3o \u00e0 conta das dota\u00e7\u00f5es consignadas no or\u00e7amento vigente<\/p>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-6-2-2-pode-isso-arnaldo\">6.2.2.&nbsp;&nbsp;&nbsp;&nbsp; Pode isso, Arnaldo?<\/h4>\n\n\n\n<p><strong><em><u>R:<\/u><\/em><\/strong> <strong>Nana-nina-N\u00c3O!!!<\/strong><\/p>\n\n\n\n<p>Isso porque, ao determinar que escolas e bibliotecas p\u00fablicas mantenham exemplares da B\u00edblia em seus acervos, <strong>a norma estadual impugnada estimula e promove certos tipos de cren\u00e7as e dogmas religiosos em DETRIMENTO de outros<\/strong>. Dessa forma, ofende os princ\u00edpios da laicidade estatal, da liberdade religiosa e da isonomia entre os cidad\u00e3os.<\/p>\n\n\n\n<p>Em mat\u00e9ria confessional, portanto, compete ao Estado manter-se NEUTRO, para preservar, em favor dos cidad\u00e3os, a integridade do direito fundamental \u00e0 liberdade religiosa.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-6-2-3-resultado-final\">6.2.3.&nbsp; Resultado final.<\/h4>\n\n\n\n<p>Com base nesse entendimento, o Plen\u00e1rio julgou procedente pedido formulado em a\u00e7\u00e3o direta e declarou a inconstitucionalidade dos arts. 1\u00ba, 2\u00ba e 4\u00ba da Lei \u201cPromulgada\u201d 74\/2010 do estado do Amazonas.<\/p>\n\n\n\n<h1 class=\"wp-block-heading\" id=\"h-direito-constitucional-e-tribut-rio\"><a>DIREITO CONSTITUCIONAL E TRIBUT\u00c1RIO<\/a><\/h1>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-7-imunidade-tribut-ria-opera-es-financeiras-e-iof\"><a>7.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Imunidade tribut\u00e1ria: opera\u00e7\u00f5es financeiras e IOF<\/a><\/h2>\n\n\n\n<p><strong>RECURSO EXTRAORDIN\u00c1RIO<\/strong><\/p>\n\n\n\n<p>A imunidade assegurada pelo art. 150, VI, \u2018c\u2019, da Constitui\u00e7\u00e3o da Rep\u00fablica aos partidos pol\u00edticos, inclusive suas funda\u00e7\u00f5es, \u00e0s entidades sindicais dos trabalhadores e \u00e0s institui\u00e7\u00f5es de educa\u00e7\u00e3o e de assist\u00eancia social, sem fins lucrativos, que atendam aos requisitos da lei, alcan\u00e7a o IOF, inclusive o incidente sobre aplica\u00e7\u00f5es financeiras<\/p>\n\n\n\n<p>RE 611510\/SP, relatora Min. Rosa Weber, julgamento virtual finalizado em 12.4.2021 (Info 1012)<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-7-1-situa-o-f-tica\"><a>7.1. Situa\u00e7\u00e3o F\u00c1TICA.<\/a><\/h3>\n\n\n\n<p>A Uni\u00e3o interp\u00f4s Recurso Extraordin\u00e1rio para discutir se o Imposto sobre Opera\u00e7\u00f5es Financeiras (IOF) incide sobre aplica\u00e7\u00f5es financeiras de curto prazo estaria \u2013 ou n\u00e3o \u2013 coberto pela imunidade tribut\u00e1ria, disposta no artigo 150, inciso VI, al\u00ednea \u201cc\u201d, da Constitui\u00e7\u00e3o Federal.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-7-2-an-lise-estrat-gica\"><a>7.2. An\u00e1lise ESTRAT\u00c9GICA.<\/a><\/h3>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-7-2-1-quest-o-jur-dica\">7.2.1.&nbsp; Quest\u00e3o JUR\u00cdDICA.<\/h4>\n\n\n\n<p>Constitui\u00e7\u00e3o Federal:<\/p>\n\n\n\n<p>Art. 150. Sem preju\u00edzo de outras garantias asseguradas ao contribuinte, \u00e9 vedado \u00e0 Uni\u00e3o, aos Estados, ao Distrito Federal e aos Munic\u00edpios:<\/p>\n\n\n\n<p>VI &#8211; instituir impostos sobre:<\/p>\n\n\n\n<p>c) patrim\u00f4nio, renda ou servi\u00e7os dos partidos pol\u00edticos, inclusive suas funda\u00e7\u00f5es, das entidades sindicais dos trabalhadores, das institui\u00e7\u00f5es de educa\u00e7\u00e3o e de assist\u00eancia social, sem fins lucrativos, atendidos os requisitos da lei:<\/p>\n\n\n\n<p>4\u00ba &#8211; As veda\u00e7\u00f5es expressas no inciso VI, al\u00edneas \u2018b\u2019 e \u2018c\u2019, compreendem somente o patrim\u00f4nio, a renda e os servi\u00e7os, relacionados com as finalidades essenciais das entidades nelas mencionadas.<\/p>\n\n\n\n<p>Art. 153. Compete \u00e0 Uni\u00e3o instituir impostos sobre:<\/p>\n\n\n\n<p>V &#8211; opera\u00e7\u00f5es de cr\u00e9dito, c\u00e2mbio e seguro, ou relativas a t\u00edtulos ou valores mobili\u00e1rios<\/p>\n\n\n\n<p>Decreto 6.306\/2007:<\/p>\n\n\n\n<p>Art. 2\u00ba \u00a7 3\u00ba N\u00e3o se submetem \u00e0 incid\u00eancia do imposto de que trata este Decreto as opera\u00e7\u00f5es realizadas por \u00f3rg\u00e3os da administra\u00e7\u00e3o direta da Uni\u00e3o, dos Estados, do Distrito Federal e dos Munic\u00edpios, e, desde que vinculadas \u00e0s finalidades essenciais das respectivas entidades, as opera\u00e7\u00f5es realizadas por:<\/p>\n\n\n\n<p>I &#8211; autarquias e funda\u00e7\u00f5es institu\u00eddas e mantidas pelo Poder P\u00fablico;<\/p>\n\n\n\n<p>II &#8211; templos de qualquer culto;<\/p>\n\n\n\n<p>III &#8211; partidos pol\u00edticos, inclusive suas funda\u00e7\u00f5es, entidades sindicais de trabalhadores e institui\u00e7\u00f5es de educa\u00e7\u00e3o e de assist\u00eancia social, sem fins lucrativos, atendidos os requisitos da lei.<\/p>\n\n\n\n<p>Lei 5.172\/1966:<\/p>\n\n\n\n<p>Art. 14. O disposto na al\u00ednea c do inciso IV do artigo 9\u00ba \u00e9 subordinado \u00e0 observ\u00e2ncia dos seguintes requisitos pelas entidades nele referidas:<\/p>\n\n\n\n<p>I \u2013 n\u00e3o distribu\u00edrem qualquer parcela de seu patrim\u00f4nio ou de suas rendas, a qualquer t\u00edtulo;<\/p>\n\n\n\n<p>\u00a7 1\u00ba Na falta de cumprimento do disposto neste artigo, ou no \u00a7 1\u00ba do artigo 9\u00ba, a autoridade competente pode suspender a aplica\u00e7\u00e3o do benef\u00edcio..<\/p>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-7-2-2-a-imunidade-dos-partidos-pol-ticos-abrange-at-mesmo-o-iof-sobre-aplica-es-financeiras\">7.2.2.&nbsp;&nbsp;&nbsp;&nbsp; A imunidade dos partidos pol\u00edticos abrange at\u00e9 mesmo o IOF sobre aplica\u00e7\u00f5es financeiras?<\/h4>\n\n\n\n<p><strong><em><u>R:<\/u><\/em><\/strong> <strong>SIM!!! (Procura-se pessoas desinteressadas para fundar um partido pol\u00edtico&#8230;)<\/strong><\/p>\n\n\n\n<p>De fato, a imunidade do art. 150, VI, c, da CF tem uma finalidade geral, de proteger direitos individuais dos cidad\u00e3os frente ao poder lesivo da tributa\u00e7\u00e3o, e distintas finalidades espec\u00edficas, cada uma delas relacionada \u00e0 \u00e1rea de atua\u00e7\u00e3o da entidade imune.<\/p>\n\n\n\n<p>A imunidade dos partidos pol\u00edticos destina-se a garantir o regime democr\u00e1tico e o livre exerc\u00edcio dos direitos pol\u00edticos; a das suas funda\u00e7\u00f5es, a tutelar a realiza\u00e7\u00e3o do seu escopo prec\u00edpuo de difundir a ideologia partid\u00e1ria e promover o exerc\u00edcio da cidadania; a das entidades sindicais dos trabalhadores, a assegurar o pleno exerc\u00edcio da liberdade de associa\u00e7\u00e3o sindical e dos direitos individuais e coletivos dos trabalhadores; a das institui\u00e7\u00f5es de educa\u00e7\u00e3o e de assist\u00eancia social, sem fins lucrativos, a proteger direitos sociais, como os direitos \u00e0 educa\u00e7\u00e3o, \u00e0 sa\u00fade, ao livre desenvolvimento da personalidade e \u00e0 assist\u00eancia social.<\/p>\n\n\n\n<p>Portanto, essas institui\u00e7\u00f5es desempenham um papel ESSENCIAL na nossa sociedade, atuando ao lado do Estado na concretiza\u00e7\u00e3o dos direitos fundamentais, que o Poder P\u00fablico n\u00e3o logra realizar de forma \u00f3tima. S\u00e3o essas finalidades que devem nortear a defini\u00e7\u00e3o do alcance da referida imunidade.<\/p>\n\n\n\n<p>Por essa raz\u00e3o, N\u00c3O se pode conferir aos voc\u00e1bulos \u201cpatrim\u00f4nio\u201d e \u201crenda\u201d, inscritos no art. 150, \u00a7 4\u00ba, da CF, interpreta\u00e7\u00e3o demasiado restritiva, que exponha \u00e0 tributa\u00e7\u00e3o as movimenta\u00e7\u00f5es patrimoniais (financeiras) e a renda obtida com opera\u00e7\u00f5es financeiras.<\/p>\n\n\n\n<p>O chamado IOF \u00e9 o imposto previsto no art. 153, V, da CF, que incide sobre \u201copera\u00e7\u00f5es de cr\u00e9dito, c\u00e2mbio e seguro, ou relativas a t\u00edtulos ou valores mobili\u00e1rios\u201d. Embora, juridicamente, a tributa\u00e7\u00e3o incida sobre essas opera\u00e7\u00f5es, acaba por, efetivamente, alcan\u00e7ar o patrim\u00f4nio ou a renda dos respectivos contribuintes. Ademais, o art. 2\u00ba, \u00a7 3\u00ba, do pr\u00f3prio Regulamento do IOF, aprovado pelo Decreto 6.306\/2007, estabelece expressamente que o imposto n\u00e3o incide sobre as opera\u00e7\u00f5es realizadas pelos entes imunes, desde que vinculadas \u00e0s finalidades essenciais destes.<\/p>\n\n\n\n<p>A exig\u00eancia de vincula\u00e7\u00e3o do patrim\u00f4nio, da renda e dos servi\u00e7os com as \u201cfinalidades essenciais\u201d da entidade imune n\u00e3o se confunde com afeta\u00e7\u00e3o direta e exclusiva a tais finalidades.<\/p>\n\n\n\n<p>Isso porque a vincula\u00e7\u00e3o \u00e9 presumida, pois as entidades arroladas no art. 150, VI, c, da CF est\u00e3o impedidas de distribuir qualquer parcela do seu patrim\u00f4nio ou de suas rendas, sob pena de suspens\u00e3o ou cancelamento do direito \u00e0 imunidade, conforme preceitua o C\u00f3digo Tribut\u00e1rio Nacional (CTN) [Lei 5.172\/1966, art. 14, I e \u00a7 1\u00ba. Com base nessa premissa, o Supremo Tribunal Federal editou a S\u00famula Vinculante 52.<\/p>\n\n\n\n<p>Dessa forma, <strong>para o reconhecimento da imunidade basta que n\u00e3o seja provado desvio de finalidade, \u00f4nus que incumbe ao sujeito ativo<\/strong>.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-7-2-3-resultado-final\">7.2.3.&nbsp; Resultado final.<\/h4>\n\n\n\n<p>Com base nesse entendimento, o Plen\u00e1rio, por unanimidade, ao apreciar o Tema 328 da repercuss\u00e3o geral, negou provimento ao recurso extraordin\u00e1rio. O ministro Alexandre de Moraes acompanhou o voto da relatora com ressalvas.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-8-contribui-o-ao-incra-natureza-jur-dica-folha-de-sal-rios-e-ec-33-2001\"><a>8.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Contribui\u00e7\u00e3o ao Incra: natureza jur\u00eddica, folha de sal\u00e1rios e EC 33\/2001<\/a><\/h2>\n\n\n\n<p><strong>RECURSO EXTRAORDIN\u00c1RIO<\/strong><\/p>\n\n\n\n<p>\u00c9 constitucional a contribui\u00e7\u00e3o de interven\u00e7\u00e3o no dom\u00ednio econ\u00f4mico destinada ao INCRA devida pelas empresas urbanas e rurais, inclusive ap\u00f3s o advento da EC n\u00ba 33\/2001(1). A contribui\u00e7\u00e3o devida ao Incra subsiste e tem natureza jur\u00eddica de contribui\u00e7\u00e3o de interven\u00e7\u00e3o no dom\u00ednio econ\u00f4mico (CIDE)(2)<\/p>\n\n\n\n<p>RE 630898\/RS, relator Min. Dias Toffoli, julgamento virtual finalizado em 7.4.2021 (Info 1012)<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-8-1-situa-o-f-tica\"><a>8.1. Situa\u00e7\u00e3o F\u00c1TICA.<\/a><\/h3>\n\n\n\n<p>Uma metal\u00fargica interp\u00f4s Recurso Extraordin\u00e1rio contra decis\u00e3o do Tribunal Regional Federal da 4\u00aa Regi\u00e3o (TRF-4) que considerou que o adicional de 0,2% fora recepcionado pela Constitui\u00e7\u00e3o de 1988 na categoria de Contribui\u00e7\u00e3o de Interven\u00e7\u00e3o no Dom\u00ednio Econ\u00f4mico (Cide).<\/p>\n\n\n\n<p>No STF, a empresa sustentou que a cobran\u00e7a, prevista na Lei 2.613\/1955 (modificada pelo Decreto-lei 1.146\/1970), seria incompat\u00edvel com a atual ordem constitucional.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-8-2-an-lise-estrat-gica\"><a>8.2. An\u00e1lise ESTRAT\u00c9GICA.<\/a><\/h3>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-8-2-1-quest-o-jur-dica\">8.2.1.&nbsp; Quest\u00e3o JUR\u00cdDICA.<\/h4>\n\n\n\n<p>Constitui\u00e7\u00e3o Federal:<\/p>\n\n\n\n<p>Art. 149. Compete exclusivamente \u00e0 Uni\u00e3o instituir contribui\u00e7\u00f5es sociais, de interven\u00e7\u00e3o no dom\u00ednio econ\u00f4mico e de interesse das categorias profissionais ou econ\u00f4micas, como instrumento de sua atua\u00e7\u00e3o nas respectivas \u00e1reas, observado o disposto nos arts. 146, III, e 150, I e III, e sem preju\u00edzo do previsto no art. 195, \u00a7 6\u00ba, relativamente \u00e0s contribui\u00e7\u00f5es a que alude o dispositivo.<\/p>\n\n\n\n<p>\u00a7 2\u00ba As contribui\u00e7\u00f5es sociais e de interven\u00e7\u00e3o no dom\u00ednio econ\u00f4mico de que trata o caput deste artigo:<\/p>\n\n\n\n<p>&nbsp;I \u2013 n\u00e3o incidir\u00e3o sobre as receitas decorrentes de exporta\u00e7\u00e3o;<\/p>\n\n\n\n<p>II \u2013 incidir\u00e3o tamb\u00e9m sobre a importa\u00e7\u00e3o de produtos estrangeiros ou servi\u00e7os;<\/p>\n\n\n\n<p>III \u2013 poder\u00e3o ter al\u00edquotas:<\/p>\n\n\n\n<p>a) ad valorem, tendo por base o faturamento, a receita bruta ou o valor da opera\u00e7\u00e3o e, no caso de importa\u00e7\u00e3o, o valor aduaneiro;<\/p>\n\n\n\n<p>b) espec\u00edfica, tendo por base a unidade de medida adotada.<\/p>\n\n\n\n<p>\u00a7 4\u00ba A lei definir\u00e1 as hip\u00f3teses em que as contribui\u00e7\u00f5es incidir\u00e3o uma \u00fanica vez<\/p>\n\n\n\n<p>Art. 170. A ordem econ\u00f4mica, fundada na valoriza\u00e7\u00e3o do trabalho humano e na livre iniciativa, tem por fim assegurar a todos exist\u00eancia digna, conforme os ditames da justi\u00e7a social, observados os seguintes princ\u00edpios:<\/p>\n\n\n\n<p>III \u2013 fun\u00e7\u00e3o social da propriedade;<\/p>\n\n\n\n<p>VII \u2013 redu\u00e7\u00e3o das desigualdades regionais e sociais;<\/p>\n\n\n\n<p>Art. 184. Compete \u00e0 Uni\u00e3o desapropriar por interesse social, para fins de reforma agr\u00e1ria, o im\u00f3vel rural que n\u00e3o esteja cumprindo sua fun\u00e7\u00e3o social, mediante pr\u00e9via e justa indeniza\u00e7\u00e3o em t\u00edtulos da d\u00edvida agr\u00e1ria, com cl\u00e1usula de preserva\u00e7\u00e3o do valor real, resgat\u00e1veis no prazo de at\u00e9 vinte anos, a partir do segundo ano de sua emiss\u00e3o, e cuja utiliza\u00e7\u00e3o ser\u00e1 definida em lei.<\/p>\n\n\n\n<p>Art. 195. A seguridade social ser\u00e1 financiada por toda a sociedade, de forma direta e indireta, nos termos da lei, mediante recursos provenientes dos or\u00e7amentos da Uni\u00e3o, dos Estados, do Distrito Federal e dos Munic\u00edpios, e das seguintes contribui\u00e7\u00f5es sociais:<\/p>\n\n\n\n<p>I &#8211; do empregador, da empresa e da entidade a ela equiparada na forma da lei, incidentes sobre:<\/p>\n\n\n\n<p>a) a folha de sal\u00e1rios e demais rendimentos do trabalho pagos ou creditados, a qualquer t\u00edtulo, \u00e0 pessoa f\u00edsica que lhe preste servi\u00e7o, mesmo sem v\u00ednculo empregat\u00edcio;<\/p>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-8-2-2-devido-o-tributo-destinado-ao-incra\">8.2.2.&nbsp;&nbsp;&nbsp;&nbsp; Devido o tributo destinado ao INCRA?<\/h4>\n\n\n\n<p><strong><em><u>R:<\/u><\/em><\/strong> <strong>SIM!!!<\/strong><\/p>\n\n\n\n<p>A contribui\u00e7\u00e3o ao Incra \u00e9 especialmente destinada a concretizar objetivos de atua\u00e7\u00e3o positiva do Estado estampados nos arts. 170, III e VII, e 184 da Constitui\u00e7\u00e3o Federal , consistentes na promo\u00e7\u00e3o da reforma agr\u00e1ria e da coloniza\u00e7\u00e3o, com vistas a assegurar o exerc\u00edcio da fun\u00e7\u00e3o social da propriedade e a diminuir as desigualdades regionais e sociais. Por seu interm\u00e9dio, a autarquia promove o equil\u00edbrio no dom\u00ednio econ\u00f4mico e, consequentemente, a justi\u00e7a social. A finalidade da contribui\u00e7\u00e3o em debate est\u00e1 em conson\u00e2ncia com a determina\u00e7\u00e3o constante do art. 149 da CF no sentido de que CIDE deve constituir instrumento de inger\u00eancia da Uni\u00e3o na ordem econ\u00f4mica. N\u00e3o descaracteriza a exa\u00e7\u00e3o o fato de o sujeito passivo (empresa urbana ou agroind\u00fastria) n\u00e3o se beneficiar diretamente da arrecada\u00e7\u00e3o, at\u00e9 porque a inexist\u00eancia de uma referibilidade direta n\u00e3o desnatura a CIDE, estando a institui\u00e7\u00e3o \u201cjungida aos princ\u00edpios gerais da atividade econ\u00f4mica\u201d.<\/p>\n\n\n\n<p>Registra-se que, por n\u00e3o se tratar de contribui\u00e7\u00e3o para a seguridade social, a parcela de 0,2% sobre a folha de sal\u00e1rios destinada ao Incra n\u00e3o foi suprimida com a Lei 7.787\/1989, tampouco com a unifica\u00e7\u00e3o dos regimes de previd\u00eancia urbana e rural levada a cabo pela Lei 8.213\/1991. De igual modo, como o produto arrecadado com a contribui\u00e7\u00e3o ao Incra n\u00e3o \u00e9 destinado a qualquer dos programas ou iniciativas da seguridade social definidos pelos arts. 194 e seguintes da CF, s\u00e3o inaplic\u00e1veis \u00e0 hip\u00f3tese as restri\u00e7\u00f5es pr\u00f3prias \u00e0s respectivas contribui\u00e7\u00f5es de custeio.<\/p>\n\n\n\n<p>A CIDE destinada ao Incra foi recepcionada pela CF, mesmo ap\u00f3s o advento da Emenda Constitucional (EC) 33\/2001. A inser\u00e7\u00e3o do \u00a7 2\u00ba, III, \u201ca\u201d, no art. 149 da Constitui\u00e7\u00e3o n\u00e3o tem o alcance de derrogar todo o arcabou\u00e7o normativo das contribui\u00e7\u00f5es sociais e de interven\u00e7\u00e3o no dom\u00ednio econ\u00f4mico que incidiam sobre a folha de sal\u00e1rios, quando da promulga\u00e7\u00e3o da referida emenda constitucional, institu\u00eddas com base no \u201ccaput\u201d do art. 149.<\/p>\n\n\n\n<p>A EC 33\/2001 e a EC 42\/2003 promoveram relevantes modifica\u00e7\u00f5es, introduzidas pelo poder constituinte derivado, que devem ser interpretadas como uma clara pol\u00edtica de utilizar, no Sistema Tribut\u00e1rio Nacional, a base econ\u00f4mica folha de sal\u00e1rios de modo mais contido. O dispositivo constitucional em quest\u00e3o n\u00e3o impede que o legislador adote, como base econ\u00f4mica, a folha de sal\u00e1rios. Uma exegese restritiva n\u00e3o se ajustaria \u00e0 sistem\u00e1tica das contribui\u00e7\u00f5es interventivas, considerada a possibilidade de atua\u00e7\u00e3o concreta do Estado para a consecu\u00e7\u00e3o dos princ\u00edpios da ordem econ\u00f4mica a que alude o art. 170 da CF.<\/p>\n\n\n\n<p>Contudo, caso se parta de premissa de que o rol das bases econ\u00f4micas enunciadas no art. 149, \u00a7 2\u00ba, III, a, da CF \u00e9 taxativo, e n\u00e3o meramente enunciativo ou exemplificativo, vislumbra-se que a altera\u00e7\u00e3o constitucional orienta o legislador \u201cpara o futuro\u201d. \u00c9 de se conferir racionalidade ao processo de concretiza\u00e7\u00e3o das normas constitucionais. N\u00e3o parece ter sido inten\u00e7\u00e3o do constituinte derivado, com a emenda, revogar, de pronto, a contribui\u00e7\u00e3o ao Incra e, durante o lapso de custeio, conferir m\u00ednima ou nenhuma efetividade aos valores e interesses constitucionais tutelados pelo Instituto. Esse entendimento \u00e9 corroborado pela EC 42\/2003 que prev\u00ea salutar substitui\u00e7\u00e3o gradual das contribui\u00e7\u00f5es incidentes sobre a folha de sal\u00e1rios institu\u00eddas com base no art. 195, I, a, da CF.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-8-2-3-resultado-final\">8.2.3.&nbsp; Resultado final.<\/h4>\n\n\n\n<p>Ao apreciar o Tema 495 da repercuss\u00e3o geral, o Plen\u00e1rio, por maioria, negou provimento a recurso extraordin\u00e1rio. Vencidos os ministros Marco Aur\u00e9lio, Rosa Weber, Ricardo Lewandowski e Edson Fachin.<\/p>\n\n\n\n<h1 class=\"wp-block-heading\" id=\"h-direito-constitucional-e-da-sa-de\"><a>DIREITO CONSTITUCIONAL E DA SA\u00daDE<\/a><\/h1>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-9-covid-19-leitos-de-uti-e-custeio-e-financiamento-pela-uni-o\"><a>9.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Covid-19: leitos de UTI e custeio e financiamento pela Uni\u00e3o<\/a><\/h2>\n\n\n\n<p><strong>A\u00c7\u00c3O CIVIL ORIGIN\u00c1RIA<\/strong><\/p>\n\n\n\n<p>Em condi\u00e7\u00f5es de recrudescimento da pandemia do novo coronav\u00edrus (Covid-19), n\u00e3o \u00e9 constitucionalmente aceit\u00e1vel qualquer retrocesso nas pol\u00edticas p\u00fablicas de sa\u00fade, como a que resulta em decr\u00e9scimo no n\u00famero de leitos de Unidade de Terapia Intensiva (UTI) habilitados (custeados) pela Uni\u00e3o.<\/p>\n\n\n\n<p>ACO 3473 MC-Ref\/DF, relatora Min. Rosa Weber, julgamento virtual finalizado em 7.4.2021(Info 1012)<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-9-1-situa-o-f-tica\"><a>9.1. Situa\u00e7\u00e3o F\u00c1TICA.<\/a><\/h3>\n\n\n\n<p>Os governadores de cinco estados-membros ajuizaram A\u00e7\u00f5es C\u00edveis Origin\u00e1rias no Supremo Tribunal Federal (STF) em que pedem a concess\u00e3o de tutela de urg\u00eancia para que o Minist\u00e9rio da Sa\u00fade seja obrigado a reativar, com a retomada do custeio, leitos de UTI exclusivos para o tratamento da Covid-19 que foram desativados ap\u00f3s dezembro de 2020.<\/p>\n\n\n\n<p>Desde o in\u00edcio da pandemia, a Uni\u00e3o instituiu sistem\u00e1tica espec\u00edfica para a habilita\u00e7\u00e3o desses leitos, com di\u00e1rias de R$ 1.600 por leito, custeadas pelo Minist\u00e9rio da Sa\u00fade. Ocorre que ap\u00f3s a desativa\u00e7\u00e3o dos leitos ao final de 2020, o Minist\u00e9rio da Sa\u00fade estaria recusando a reativa\u00e7\u00e3o destes, justamente em momento de recrudescimento da pandemia&#8230;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-9-2-an-lise-estrat-gica\"><a>9.2. An\u00e1lise ESTRAT\u00c9GICA.<\/a><\/h3>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-9-2-1-reativa-e-paga-os-leitos-de-uti\">9.2.1.&nbsp;&nbsp;&nbsp;&nbsp; Reativa e paga os leitos de UTI?<\/h4>\n\n\n\n<p><strong><em><u>R:<\/u><\/em><\/strong> <strong>COM CERTEZA, PARA ONTEM!!!<\/strong><\/p>\n\n\n\n<p>O recrudescimento das taxas de contamina\u00e7\u00e3o, interna\u00e7\u00e3o e letalidade em decorr\u00eancia da pandemia da Covid-19 \u00e9 incontroverso e not\u00f3rio. Nesse cen\u00e1rio, s\u00e3o PREOCUPANTES as alega\u00e7\u00f5es de estado federado no sentido de que a Uni\u00e3o n\u00e3o tem se posicionado sobre requerimento de habilita\u00e7\u00e3o de novos leitos de UTI e de que os leitos financiados com recursos federais, destinados exclusivamente ao tratamento de pacientes com Covid-19, t\u00eam sido desabilitados.<\/p>\n\n\n\n<p>A prop\u00f3sito da tramita\u00e7\u00e3o de cr\u00e9dito or\u00e7ament\u00e1rio extraordin\u00e1rio para fazer frente \u00e0s vulnerabilidades, as vidas em jogo n\u00e3o podem ficar na depend\u00eancia da burocracia estatal ou das idiossincrasias pol\u00edticas. Est\u00e3o em xeque cl\u00e1usulas vitais de sa\u00fade coletiva. Al\u00e9m disso, a solu\u00e7\u00e3o de conflitos sobre o exerc\u00edcio da compet\u00eancia deve pautar-se pela melhor realiza\u00e7\u00e3o do direito \u00e0 sa\u00fade. Identificada omiss\u00e3o estatal ou gerenciamento err\u00e1tico, como aparentemente se apresenta, \u00e9 vi\u00e1vel a interfer\u00eancia judicial para a concretiza\u00e7\u00e3o do direito social \u00e0 sa\u00fade, cujas a\u00e7\u00f5es e servi\u00e7os s\u00e3o marcados constitucionalmente pelo acesso igualit\u00e1rio e universal.<\/p>\n\n\n\n<p>Deve ser exigido do governo federal que suas a\u00e7\u00f5es sejam respaldadas por crit\u00e9rios T\u00c9CNICOS e CIENT\u00cdFICOS, e que sejam implantadas as pol\u00edticas p\u00fablicas a partir de atos administrativos l\u00f3gicos e coerentes. N\u00e3o \u00e9 l\u00f3gico, coerente ou cientificamente defens\u00e1vel a diminui\u00e7\u00e3o do n\u00famero de leitos de UTI custodiados pela Uni\u00e3o em momento desafiador da pandemia, justamente quando constatado incremento das mortes e das interna\u00e7\u00f5es hospitalares.<strong> Cumpre enfatizar que a program\u00e1tica constitucional n\u00e3o placita retrocessos injustificados no direito social \u00e0 sa\u00fade<\/strong>. Em ju\u00edzo de deliba\u00e7\u00e3o, evidencia-se a presen\u00e7a do requisito da probabilidade do direito.<\/p>\n\n\n\n<p>Afigura-se, ainda, o perigo da demora, que se revela intuitivo frente aos abalos causados pela pandemia. N\u00e3o h\u00e1 nada mais urgente do que o desejo de viver. O n\u00e3o endere\u00e7amento \u00e1gil e racional do problema pode multiplicar o n\u00famero de \u00f3bitos e potencializar a trag\u00e9dia humanit\u00e1ria.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-9-2-2-resultado-final\">9.2.2.&nbsp; Resultado final.<\/h4>\n\n\n\n<p>Em julgamento conjunto, o Plen\u00e1rio referendou tutelas de urg\u00eancia concedidas em cinco a\u00e7\u00f5es c\u00edveis origin\u00e1rias, propostas por estados-membros da Federa\u00e7\u00e3o, para: (i) determinar \u00e0 Uni\u00e3o Federal que analise, imediatamente, os pedidos de habilita\u00e7\u00e3o de novos leitos de UTI formulados pelos estados-membros requerentes junto ao Minist\u00e9rio da Sa\u00fade; (ii) determinar \u00e0 Uni\u00e3o que restabele\u00e7a, imediatamente, de forma proporcional \u00e0s outras unidades federativas, os leitos de UTI destinados ao tratamento da Covid-19 nos estados requerentes que estavam habilitados (custeados) pelo Minist\u00e9rio da Sa\u00fade at\u00e9 dezembro de 2020, e que foram reduzidos nos meses de janeiro e fevereiro de 2021; (iii) determinar \u00e0 Uni\u00e3o Federal que preste suporte t\u00e9cnico e financeiro para a expans\u00e3o da rede de UTI\u2019s nos entes estaduais requerentes, de forma proporcional \u00e0s outras unidades federativas, em caso de evolu\u00e7\u00e3o da pandemia. O ministro Nunes Marques acompanhou com ressalvas o voto da ministra Rosa Weber (relatora).<\/p>\n\n\n\n<h1 class=\"wp-block-heading\" id=\"h-direito-processual-civil\"><a>DIREITO PROCESSUAL CIVIL<\/a><\/h1>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-10-limite-territorial-dos-efeitos-das-decis-es-em-a-o-civil-p-blica-art-16-da-lei-7-347-1985\"><a>10.&nbsp; Limite territorial dos efeitos das decis\u00f5es em a\u00e7\u00e3o civil p\u00fablica: art. 16 da Lei 7.347\/1985<\/a><\/h2>\n\n\n\n<p><strong>RECURSO ESPECIAL<\/strong><\/p>\n\n\n\n<p>I &#8211; \u00c9 inconstitucional o art. 16 da Lei 7.347\/1985, alterada pela Lei 9.494\/1997. II &#8211; Em se tratando de a\u00e7\u00e3o civil p\u00fablica de efeitos nacionais ou regionais, a compet\u00eancia deve observar o art. 93, II, da Lei 8.078\/1990. III &#8211; Ajuizadas m\u00faltiplas a\u00e7\u00f5es civis p\u00fablicas de \u00e2mbito nacional ou regional, firma-se a preven\u00e7\u00e3o do ju\u00edzo que primeiro conheceu de uma delas, para o julgamento de todas as demandas conexas<\/p>\n\n\n\n<p>RE 1101973\/SP, relator Min. Alexandre de Moraes, julgamento virtual finalizado em 7.4.2021(Info 1012)<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-10-1-situa-o-f-tica\"><a>10.1.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Situa\u00e7\u00e3o F\u00c1TICA.<\/a><\/h3>\n\n\n\n<p>O Instituto Brasileiro de Defesa do Consumidor (IDEC) prop\u00f4s \u201cA\u00e7\u00e3o Coletiva de Revis\u00e3o Contratual\u201d, com pedido de liminar, em face de diversas entidades banc\u00e1rias buscando a revis\u00e3o de contratos de financiamento habitacional celebrados por seus associados com as referidas institui\u00e7\u00f5es financeiras.<\/p>\n\n\n\n<p>Ao proferir o despacho saneador e apreciar o pedido de tutela antecipada, o Ju\u00edzo de primeiro grau determinou (i) a suspens\u00e3o da efic\u00e1cia das cl\u00e1usulas contratuais que autorizam as institui\u00e7\u00f5es financeiras a promover a execu\u00e7\u00e3o extrajudicial prevista no Decreto-Lei 70\/1966 e (ii) a susta\u00e7\u00e3o das execu\u00e7\u00f5es j\u00e1 iniciadas, sob pena de multa di\u00e1ria.<\/p>\n\n\n\n<p>Em recurso, o Tribunal Regional Federal local entendeu pela inaplicabilidade do art. 16 da Lei 7.347\/1985 (Lei da A\u00e7\u00e3o Civil P\u00fablica), pois o direito reconhecido na causa n\u00e3o pode ficar restrito a um \u00e2mbito regional, dada a amplitude dos interesses em jogo, o que levou um dos bancos a interpor Recurso Extraordin\u00e1rio no qual questionou a constitucionalidade do art. 16 da Lei 7.347\/1985.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-10-2-an-lise-estrat-gica\"><a>10.2.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; An\u00e1lise ESTRAT\u00c9GICA.<\/a><\/h3>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-10-2-1-quest-o-jur-dica\">10.2.1.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Quest\u00e3o JUR\u00cdDICA.<\/h4>\n\n\n\n<p>Lei 7.347\/1985:<\/p>\n\n\n\n<p>Art. 2\u00ba As a\u00e7\u00f5es previstas nesta Lei ser\u00e3o propostas no foro do local onde ocorrer o dano, cujo ju\u00edzo ter\u00e1 compet\u00eancia funcional para processar e julgar a causa.<\/p>\n\n\n\n<p>Par\u00e1grafo \u00fanico. A propositura da a\u00e7\u00e3o prevenir\u00e1 a jurisdi\u00e7\u00e3o do ju\u00edzo para todas as a\u00e7\u00f5es posteriormente intentadas que possuam a mesma causa de pedir ou o mesmo objeto<\/p>\n\n\n\n<p>Art. 16. A senten\u00e7a civil far\u00e1 coisa julgada erga omnes, nos limites da compet\u00eancia territorial do \u00f3rg\u00e3o prolator, exceto se o pedido for julgado improcedente por insufici\u00eancia de provas, hip\u00f3tese em que qualquer legitimado poder\u00e1 intentar outra a\u00e7\u00e3o com id\u00eantico fundamento, valendo-se de nova prova.<\/p>\n\n\n\n<p>Art. 21. Aplicam-se \u00e0 defesa dos direitos e interesses difusos, coletivos e individuais, no que for cab\u00edvel, os dispositivos do T\u00edtulo III da lei que instituiu o C\u00f3digo de Defesa do Consumidor.<\/p>\n\n\n\n<p>Lei 8.078\/1990:<\/p>\n\n\n\n<p>Art. 90. Aplicam-se \u00e0s a\u00e7\u00f5es previstas neste t\u00edtulo as normas do C\u00f3digo de Processo Civil e da Lei n\u00b0 7.347, de 24 de julho de 1985, inclusive no que respeita ao inqu\u00e9rito civil, naquilo que n\u00e3o contrariar suas disposi\u00e7\u00f5es.<\/p>\n\n\n\n<p>Art. 93. Ressalvada a compet\u00eancia da Justi\u00e7a Federal, \u00e9 competente para a causa a justi\u00e7a local:<\/p>\n\n\n\n<p>II &#8211; no foro da Capital do Estado ou no do Distrito Federal, para os danos de \u00e2mbito nacional ou regional, aplicando-se as regras do C\u00f3digo de Processo Civil aos casos de compet\u00eancia concorrente.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-10-2-2-a-norma-constitucional\">10.2.2. A norma \u00e9 constitucional?<\/h4>\n\n\n\n<p><strong><em><u>R:<\/u><\/em><\/strong> <strong>N\u00c3O!!!<\/strong><\/p>\n\n\n\n<p>\u00c9 inconstitucional a delimita\u00e7\u00e3o dos efeitos da senten\u00e7a proferida em sede de a\u00e7\u00e3o civil p\u00fablica aos limites da compet\u00eancia territorial de seu \u00f3rg\u00e3o prolator.<\/p>\n\n\n\n<p>Isso porque a altera\u00e7\u00e3o do art. 16 da Lei 7.347\/1985 promovida pela Lei 9.494\/1997, fruto da convers\u00e3o da MP 1.570\/1997, veio na contram\u00e3o do avan\u00e7o institucional de prote\u00e7\u00e3o aos direitos metaindividuais e esbarra nos preceitos norteadores da tutela coletiva, bem como nos comandos pertinentes ao amplo acesso \u00e0 Justi\u00e7a e \u00e0 isonomia entre os jurisdicionados.<\/p>\n\n\n\n<p>Com efeito, com a edi\u00e7\u00e3o do C\u00f3digo de Defesa do Consumidor (CDC) &#8211; Lei 8.078\/1990, cujo art. 90, somando-se ao art. 21 da Lei da A\u00e7\u00e3o Civil P\u00fablica (LACP) &#8211; Lei 7.347\/1985, estabeleceu-se a aplica\u00e7\u00e3o m\u00fatua de ambas as normas e constitui-se verdadeiro microssistema processual coletivo.<\/p>\n\n\n\n<p>Nesse contexto, as Leis 7.347\/1985 e 8.078\/1990 seguiram o mesmo padr\u00e3o de prote\u00e7\u00e3o dos direitos metaindividuais, e \u2014 em respeito \u00e0 unidade da Constitui\u00e7\u00e3o, \u00e0 m\u00e1xima efetividade ou \u00e0 efici\u00eancia, e \u00e0 justeza ou \u00e0 conformidade funcional \u2014 n\u00e3o \u00e9 poss\u00edvel compatibilizar a indevida restri\u00e7\u00e3o criada pelo art. 16 da LACP com os princ\u00edpios da igualdade e da efici\u00eancia na presta\u00e7\u00e3o jurisdicional.<\/p>\n\n\n\n<p>A defini\u00e7\u00e3o do ju\u00edzo competente para o processamento de a\u00e7\u00f5es civis p\u00fablicas cuja senten\u00e7a tenha proje\u00e7\u00e3o regional ou nacional deve observar o disposto no art. 93, II, do CDC.<\/p>\n\n\n\n<p>Com a declara\u00e7\u00e3o de inconstitucionalidade da atual reda\u00e7\u00e3o do art. 16 da LACP, deve-se impedir a escolha de ju\u00edzos aleat\u00f3rios para o processo e julgamento de a\u00e7\u00f5es que versem sobre esses direitos difusos e coletivos.<\/p>\n\n\n\n<p>Desse modo, em se tratando de a\u00e7\u00e3o civil p\u00fablica com abrang\u00eancia nacional ou regional, sua propositura deve ocorrer no foro, ou na circunscri\u00e7\u00e3o judici\u00e1ria, de capital de estado ou no Distrito Federal. Em se tratando de alcance geograficamente superior a um estado, a op\u00e7\u00e3o por capital de estado evidentemente deve contemplar uma que esteja situada na regi\u00e3o atingida.<\/p>\n\n\n\n<p>O juiz competente, nos termos do art. 2\u00ba da LACP e do art. 93 do CDC, que primeiro conhecer da mat\u00e9ria ficar\u00e1 prevento para processar e julgar todas as demandas que proponham o mesmo objeto.<\/p>\n\n\n\n<p>A aplica\u00e7\u00e3o dessas normas torna poss\u00edvel definir qual o juiz competente, inclusive para a\u00e7\u00f5es cuja decis\u00e3o tenha efeitos regionais ou nacionais. E, uma vez fixada essa compet\u00eancia, o primeiro que conhecer da mat\u00e9ria, entre os competentes, ficar\u00e1 prevento.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-10-2-3-resultado-final\"><a>10.2.3.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Resultado final.<\/a><\/h4>\n\n\n\n<p>Com base nesse entendimento, o Plen\u00e1rio, ao apreciar o Tema 1075 da repercuss\u00e3o geral, por maioria, negou provimento a recurso extraordin\u00e1rio e declarou a inconstitucionalidade do art. 16 da Lei 7.347\/1985, com a reda\u00e7\u00e3o dada pela Lei 9.494\/1997, e, consequentemente, reconheceu a aplica\u00e7\u00e3o de efeitos repristinat\u00f3rios \u00e0 reda\u00e7\u00e3o original do dispositivo questionado. Vencido o ministro Marco Aur\u00e9lio. O ministro Edson Fachin acompanhou o relator com ressalvas.<\/p>\n\n\n\n<h1 class=\"wp-block-heading\" id=\"h-direito-processual-penal\"><a>DIREITO PROCESSUAL PENAL<\/a><\/h1>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-11-atua-o-do-juiz-e-ordem-de-inquiri-o-de-testemunhas\"><a>11.&nbsp; Atua\u00e7\u00e3o do juiz e ordem de inquiri\u00e7\u00e3o de testemunhas<\/a><\/h2>\n\n\n\n<p><strong>HABEAS CORPUS<\/strong><\/p>\n\n\n\n<p><a>N\u00e3o cabe ao juiz, na audi\u00eancia de instru\u00e7\u00e3o e julgamento de processo penal, iniciar a inquiri\u00e7\u00e3o de testemunha, cabendo-lhe, apenas, complementar a inquiri\u00e7\u00e3o sobre os pontos n\u00e3o esclarecidos<\/a><\/p>\n\n\n\n<p>HC 187035\/SP, relator Min. Marco Aur\u00e9lio, julgamento em 6.4.2021(Info 1012)<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-11-1-situa-o-f-tica\"><a>11.1.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Situa\u00e7\u00e3o F\u00c1TICA.<\/a><\/h3>\n\n\n\n<p>Em certa instru\u00e7\u00e3o criminal, o Juiz iniciou a inquiri\u00e7\u00e3o da testemunha sem observar o art. 212 do C\u00f3digo de Processo Penal que prev\u00ea a iniciativa das partes na inquiri\u00e7\u00e3o.<\/p>\n\n\n\n<p>Apesar dos protestos dos advogados de defesa, o Ju\u00edzo manteve o procedimento e passou a inquirir a testemunha. Contra o ato, a defesa ent\u00e3o impetrou sucessivos Habeas Corpus alegando a nulidade do processo-crime a partir da audi\u00eancia de instru\u00e7\u00e3o.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-11-2-an-lise-estrat-gica\"><a>11.2.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; An\u00e1lise ESTRAT\u00c9GICA.<\/a><\/h3>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-11-2-1-quest-o-jur-dica\">11.2.1.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Quest\u00e3o JUR\u00cdDICA.<\/h4>\n\n\n\n<p>C\u00f3digo de Processo Penal:<\/p>\n\n\n\n<p>Art. 156.&nbsp; A prova da alega\u00e7\u00e3o incumbir\u00e1 a quem a fizer, sendo, por\u00e9m, facultado ao juiz de of\u00edcio:<\/p>\n\n\n\n<p>Art. 212. As perguntas ser\u00e3o formuladas pelas partes diretamente \u00e0 testemunha, n\u00e3o admitindo o juiz aquelas que puderem induzir a resposta, n\u00e3o tiverem rela\u00e7\u00e3o com a causa ou importarem na repeti\u00e7\u00e3o de outra j\u00e1 respondida.<\/p>\n\n\n\n<p>Par\u00e1grafo \u00fanico. Sobre os pontos n\u00e3o esclarecidos, o juiz poder\u00e1 complementar a inquiri\u00e7\u00e3o<\/p>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-11-2-2-o-juiz-se-passou\">11.2.2. O Juiz \u201cse passou\u201d?<\/h4>\n\n\n\n<p><strong><em><u>R:<\/u><\/em><\/strong> <strong>SIM!!!<\/strong><\/p>\n\n\n\n<p>Assim disp\u00f5e o art. 212 do C\u00f3digo de Processo Penal o qual prev\u00ea a POSSIBILIDADE de o pr\u00f3prio juiz veicular perguntas <strong>apenas se verificados, ante o questionamento das partes, pontos n\u00e3o esclarecidos.<\/strong><\/p>\n\n\n\n<p>A altera\u00e7\u00e3o promovida pela Lei 11.690\/2008 modificou SUBSTANCIALMENTE a sistem\u00e1tica procedimental da inquiri\u00e7\u00e3o de testemunhas. As partes, <strong>em modelo mais consent\u00e2neo com o sistema acusat\u00f3rio, t\u00eam o protagonismo na audi\u00eancia<\/strong>. Cabe-lhes a formula\u00e7\u00e3o de perguntas DIRETAMENTE \u00e0s testemunhas. Ao juiz, como presidente da audi\u00eancia, cabe o controle do ato processual para que a prova seja produzida nos moldes legais e pertinentes ao caso.<\/p>\n\n\n\n<p>Ele n\u00e3o atua como mero espectador, mas exerce, no tocante \u00e0 produ\u00e7\u00e3o da prova testemunhal, especificamente quanto \u00e0 formula\u00e7\u00e3o de perguntas \u00e0s testemunhas, papel subsidi\u00e1rio, secund\u00e1rio, de modo que somente \u00e9 leg\u00edtima sua atividade instrut\u00f3ria ap\u00f3s o pr\u00e9vio exerc\u00edcio do direito \u00e0 prova pelas partes e para saneamento de d\u00favida quanto a aspectos n\u00e3o esclarecidos e relevantes.<\/p>\n\n\n\n<p>N\u00e3o pode o magistrado, em substitui\u00e7\u00e3o \u00e0 atua\u00e7\u00e3o das partes, ser o protagonista do ato de inquiri\u00e7\u00e3o e tomar para si o papel de primeiro questionador das testemunhas, mesmo porque compete \u00e0s partes a comprova\u00e7\u00e3o do quanto alegado.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-11-2-3-resultado-final\">11.2.3.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Resultado final.<\/h4>\n\n\n\n<p>Com base nesse entendimento, a Primeira Turma, por maioria, deferiu a ordem de habeas corpus, para reconhecer a nulidade do processo-crime a partir da audi\u00eancia de instru\u00e7\u00e3o, com a necess\u00e1ria renova\u00e7\u00e3o do ato. Vencidos os ministros Alexandre de Moraes e Lu\u00eds Roberto Barroso.<\/p>\n\n\n\n<div class=\"wp-block-file\"><a href=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/04\/19225554\/stf-1012-1.pdf\">stf-1012-1<\/a><a href=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/04\/19225554\/stf-1012-1.pdf\" class=\"wp-block-file__button\" download>Baixar<\/a><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Informativo n\u00ba 1012 do STF COMENTADO pintando na telinha (do seu computador, notebook, tablet, celular&#8230;) para quem est\u00e1 ligado aqui conosco no Estrat\u00e9gia Carreiras Jur\u00eddicas! DOWNLOAD do PDF AQUI! Sum\u00e1rio DIREITO ADMINISTRATIVO&#8230; 2 1.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Concession\u00e1rias de energia el\u00e9trica e utiliza\u00e7\u00e3o onerosa de faixas de dom\u00ednio p\u00fablico estadual 2 1.1.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Situa\u00e7\u00e3o F\u00c1TICA. 3 1.2.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; An\u00e1lise ESTRAT\u00c9GICA. [&hellip;]<\/p>\n","protected":false},"author":833,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"post_tipo":"article","footnotes":""},"categories":[1],"tags":[],"tax_estado":[],"class_list":["post-717421","post","type-post","status-publish","format-standard","hentry","category-cursos-e-concursos"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.2 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Informativo STF 1012 Comentado<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/informativo-stf-1012-comentado\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Informativo STF 1012 Comentado\" \/>\n<meta property=\"og:description\" content=\"Informativo n\u00ba 1012 do STF COMENTADO pintando na telinha (do seu computador, notebook, tablet, celular&#8230;) para quem est\u00e1 ligado aqui conosco no Estrat\u00e9gia Carreiras Jur\u00eddicas! DOWNLOAD do PDF AQUI! Sum\u00e1rio DIREITO ADMINISTRATIVO&#8230; 2 1.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Concession\u00e1rias de energia el\u00e9trica e utiliza\u00e7\u00e3o onerosa de faixas de dom\u00ednio p\u00fablico estadual 2 1.1.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Situa\u00e7\u00e3o F\u00c1TICA. 3 1.2.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; An\u00e1lise ESTRAT\u00c9GICA. [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/informativo-stf-1012-comentado\/\" \/>\n<meta property=\"og:site_name\" content=\"Estrat\u00e9gia Concursos\" \/>\n<meta property=\"article:published_time\" content=\"2021-04-20T01:56:21+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-04-20T14:00:36+00:00\" \/>\n<meta name=\"author\" content=\"Jean Vilbert\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:site\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jean Vilbert\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"33 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/informativo-stf-1012-comentado\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/informativo-stf-1012-comentado\/\"},\"author\":{\"name\":\"Jean Vilbert\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/475a0922f10cff0d1bc8bfecde05f999\"},\"headline\":\"Informativo STF 1012 Comentado\",\"datePublished\":\"2021-04-20T01:56:21+00:00\",\"dateModified\":\"2021-04-20T14:00:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/informativo-stf-1012-comentado\/\"},\"wordCount\":8526,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"articleSection\":[\"Concursos P\u00fablicos\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/informativo-stf-1012-comentado\/#respond\"]}],\"copyrightYear\":\"2021\",\"copyrightHolder\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/informativo-stf-1012-comentado\/\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/informativo-stf-1012-comentado\/\",\"name\":\"Informativo STF 1012 Comentado\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\"},\"datePublished\":\"2021-04-20T01:56:21+00:00\",\"dateModified\":\"2021-04-20T14:00:36+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/informativo-stf-1012-comentado\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/informativo-stf-1012-comentado\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/informativo-stf-1012-comentado\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Informativo STF 1012 Comentado\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"name\":\"Estrat\u00e9gia Concursos\",\"description\":\"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.\",\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\",\"name\":\"Estrat\u00e9gia Concursos\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"width\":230,\"height\":60,\"caption\":\"Estrat\u00e9gia Concursos\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/EstratConcursos\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/475a0922f10cff0d1bc8bfecde05f999\",\"name\":\"Jean Vilbert\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/1667694e4ebdd32feeac9ea2794de3f0470b5c55c6198181ab0b0c333b121921?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/1667694e4ebdd32feeac9ea2794de3f0470b5c55c6198181ab0b0c333b121921?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/1667694e4ebdd32feeac9ea2794de3f0470b5c55c6198181ab0b0c333b121921?s=96&d=mm&r=g\",\"caption\":\"Jean Vilbert\"},\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/jeanvilbertgmail-com\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Informativo STF 1012 Comentado","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.estrategiaconcursos.com.br\/blog\/informativo-stf-1012-comentado\/","og_locale":"pt_BR","og_type":"article","og_title":"Informativo STF 1012 Comentado","og_description":"Informativo n\u00ba 1012 do STF COMENTADO pintando na telinha (do seu computador, notebook, tablet, celular&#8230;) para quem est\u00e1 ligado aqui conosco no Estrat\u00e9gia Carreiras Jur\u00eddicas! DOWNLOAD do PDF AQUI! Sum\u00e1rio DIREITO ADMINISTRATIVO&#8230; 2 1.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Concession\u00e1rias de energia el\u00e9trica e utiliza\u00e7\u00e3o onerosa de faixas de dom\u00ednio p\u00fablico estadual 2 1.1.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Situa\u00e7\u00e3o F\u00c1TICA. 3 1.2.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; An\u00e1lise ESTRAT\u00c9GICA. [&hellip;]","og_url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/informativo-stf-1012-comentado\/","og_site_name":"Estrat\u00e9gia Concursos","article_published_time":"2021-04-20T01:56:21+00:00","article_modified_time":"2021-04-20T14:00:36+00:00","author":"Jean Vilbert","twitter_card":"summary_large_image","twitter_creator":"@EstratConcursos","twitter_site":"@EstratConcursos","twitter_misc":{"Escrito por":"Jean Vilbert","Est. tempo de leitura":"33 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/informativo-stf-1012-comentado\/#article","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/informativo-stf-1012-comentado\/"},"author":{"name":"Jean Vilbert","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/475a0922f10cff0d1bc8bfecde05f999"},"headline":"Informativo STF 1012 Comentado","datePublished":"2021-04-20T01:56:21+00:00","dateModified":"2021-04-20T14:00:36+00:00","mainEntityOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/informativo-stf-1012-comentado\/"},"wordCount":8526,"commentCount":0,"publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"articleSection":["Concursos P\u00fablicos"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/informativo-stf-1012-comentado\/#respond"]}],"copyrightYear":"2021","copyrightHolder":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/informativo-stf-1012-comentado\/","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/informativo-stf-1012-comentado\/","name":"Informativo STF 1012 Comentado","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website"},"datePublished":"2021-04-20T01:56:21+00:00","dateModified":"2021-04-20T14:00:36+00:00","breadcrumb":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/informativo-stf-1012-comentado\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/informativo-stf-1012-comentado\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/informativo-stf-1012-comentado\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.estrategiaconcursos.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Informativo STF 1012 Comentado"}]},{"@type":"WebSite","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","name":"Estrat\u00e9gia Concursos","description":"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.","publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization","name":"Estrat\u00e9gia Concursos","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","width":230,"height":60,"caption":"Estrat\u00e9gia Concursos"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/EstratConcursos"]},{"@type":"Person","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/475a0922f10cff0d1bc8bfecde05f999","name":"Jean Vilbert","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/1667694e4ebdd32feeac9ea2794de3f0470b5c55c6198181ab0b0c333b121921?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/1667694e4ebdd32feeac9ea2794de3f0470b5c55c6198181ab0b0c333b121921?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1667694e4ebdd32feeac9ea2794de3f0470b5c55c6198181ab0b0c333b121921?s=96&d=mm&r=g","caption":"Jean Vilbert"},"url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/jeanvilbertgmail-com\/"}]}},"_links":{"self":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/717421","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/users\/833"}],"replies":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/comments?post=717421"}],"version-history":[{"count":3,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/717421\/revisions"}],"predecessor-version":[{"id":719587,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/717421\/revisions\/719587"}],"wp:attachment":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media?parent=717421"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/categories?post=717421"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tags?post=717421"},{"taxonomy":"tax_estado","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tax_estado?post=717421"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}