{"id":70305,"date":"2017-04-11T09:14:08","date_gmt":"2017-04-11T12:14:08","guid":{"rendered":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?p=70305"},"modified":"2017-05-10T10:11:36","modified_gmt":"2017-05-10T13:11:36","slug":"zona-de-desconforto","status":"publish","type":"post","link":"https:\/\/www.estrategiaconcursos.com.br\/blog\/zona-de-desconforto\/","title":{"rendered":"Zona de DESconforto"},"content":{"rendered":"<p style=\"text-align: justify\">\n\t<span style=\"color:#FF0000\"><strong><span style=\"font-family:verdana,geneva,sans-serif\"><span style=\"font-size:14px\">A zona de conforto &eacute; MARAVILHOSA! Pronto, falei.<\/span><\/span><\/strong><\/span>\n<\/p>\n<p style=\"text-align: justify\">\n\t&nbsp;\n<\/p>\n<p style=\"text-align: justify\">\n\t<span style=\"font-family:verdana,geneva,sans-serif\"><span style=\"font-size:14px\"><span style=\"color:#0000CD\"><strong>Estou em crise existencial com frases de efeito.<\/strong><\/span>&nbsp;E olha que sempre as curti bastante. Mas a motiva&ccedil;&atilde;o proveniente delas &eacute; muito <strong><span style=\"color:#0000CD\">fugaz<\/span><\/strong>. E sabe por qu&ecirc;?&nbsp;Porque elas n&atilde;o s&atilde;o precisas.&nbsp;As palavras, na minha humilde opini&atilde;o, s&atilde;o mal escolhidas. <strong><span style=\"color:#0000CD\">E voc&ecirc;, ser pensante, mais cedo ou mais tarde vai question&aacute;-las e sua motiva&ccedil;&atilde;o, se excessivamente apoiadas nelas, vai evaporar.<\/span><\/strong><\/span><\/span>\n<\/p>\n<p style=\"text-align: justify\">\n\t<span style=\"font-family:verdana,geneva,sans-serif\"><span style=\"font-size:14px\">Vamos devagar!<\/span><\/span>\n<\/p>\n<p style=\"text-align: justify\">\n\t<span style=\"font-family:verdana,geneva,sans-serif\"><span style=\"font-size:14px\">Quando algu&eacute;m est&aacute; chateado com sua vida profissional, est&aacute; ganhando mal ou est&aacute; sem emprego, percebe que em seu local de trabalho n&atilde;o h&aacute; oportunidade de desenvolvimento, crescimento, aprendizagem essa pessoa n&atilde;o est&aacute; confort&aacute;vel, concorda? Alguns relatam sentir que est&atilde;o &ldquo;emburrecendo&rdquo; em determinadas empresas e at&eacute; nos t&atilde;o sonhados e duramente conquistados cargos&nbsp;p&uacute;blicos. Outros sofrem ass&eacute;dio moral. H&aacute; ainda os que n&atilde;o sentem que seu trabalho faz muita diferen&ccedil;a no mundo e ficam desmotivados, infelizes. V&aacute;rias pessoas cumulam os problemas citados acima! <span style=\"color:#0000CD\"><strong>Como posso chegar para esse aluno e motiv&aacute;-lo a estudar pedindo que saia da zona de conforto??? Voc&ecirc; t&aacute; vendo algum conforto ali? Nem eu! <\/strong><\/span>Se ficarmos repetindo esse termo que julgo t&atilde;o impreciso, nossa cabecinha tende a crer que h&aacute; algo de bom naquela situa&ccedil;&atilde;o. <span style=\"color:#0000CD\"><strong>Consequ&ecirc;ncia: faremos de TUDO para mant&ecirc;-la.<\/strong><\/span>&nbsp;Vamos dar os nomes CORRETOS para as coisas, ok?&nbsp;Assim tudo fica mais claro.<\/span><\/span>\n<\/p>\n<p style=\"text-align: justify\">\n\t&nbsp;\n<\/p>\n<p style=\"text-align: justify\">\n\t<span style=\"color:#FF0000\"><strong><span style=\"font-family:verdana,geneva,sans-serif\"><span style=\"font-size:14px\">Filho (a), voc&ecirc; est&aacute; na zona de DESCONFORTO.&nbsp;Entenda isso para podermos avan&ccedil;ar.<\/span><\/span><\/strong><\/span>\n<\/p>\n<p style=\"text-align: justify\">\n\t&nbsp;\n<\/p>\n<p style=\"text-align: justify\">\n\t<span style=\"font-family:verdana,geneva,sans-serif\"><span style=\"font-size:14px\"><span style=\"color:#0000CD\"><strong>Felizmente e, por vezes, infelizmente, o ser humano &eacute; altamente adapt&aacute;vel.&nbsp;Para ser mais direta, nos acostumamos&nbsp; com tudo.&nbsp;At&eacute; com o que &eacute; RUIM.<\/strong>&nbsp;<\/span>Seu emprego est&aacute; te deixando na &ldquo;bad&rdquo;. O que voc&ecirc; faz? Nada! Seu relacionamento est&aacute; uma droga e voc&ecirc; j&aacute; tentou de tudo. O que voc&ecirc; faz? Nada! Voc&ecirc; fica l&aacute;.<span style=\"color:#0000CD\"><strong> Preso (a) na maldita zona de DESCONFORTO! <\/strong><\/span>Fazemos isso por uma s&eacute;rie de raz&otilde;es: medo, sensa&ccedil;&atilde;o de merecer aquela situa&ccedil;&atilde;o prec&aacute;ria, sensa&ccedil;&atilde;o de d&iacute;vida com os envolvidos na situa&ccedil;&atilde;o, d&uacute;vidas acerca do pr&oacute;prio valor e at&eacute; das pr&oacute;prias vontades&#8230; os motivos variam. A sensa&ccedil;&atilde;o de DESCONFORTO &ndash; contudo &ndash; &eacute; a constante. Pense direitinho no que te mant&eacute;m ali.&nbsp;SPOILER: Apontar para o fator pregui&ccedil;a &eacute; apenas arranhar a superf&iacute;cie do problema. <span style=\"color:#0000CD\"><strong>Pregui&ccedil;a &eacute; SINTOMA. Nunca &eacute; a quest&atilde;o principal. <\/strong><\/span>O que te impede de tomar uma provid&ecirc;ncia &eacute; algo mais complexo. Tire um tempo &ldquo;voc&ecirc; com voc&ecirc;&rdquo; para refletir sobre isso.<\/span><\/span>\n<\/p>\n<p style=\"text-align: justify\">\n\t&nbsp;\n<\/p>\n<p style=\"text-align: justify\">\n\t<span style=\"font-family:verdana,geneva,sans-serif\"><span style=\"font-size:14px\">Bom, depois de termos melhorado o termo &ldquo;zona de conforto&rdquo; e analisado as raz&otilde;es que nos mant&eacute;m presos a algo que n&atilde;o nos serve, chegou a hora de pensarmos na ZONA DE REAL CONFORTO.<\/span><\/span>\n<\/p>\n<p style=\"text-align: justify\">\n\t&nbsp;\n<\/p>\n<p style=\"text-align: justify\">\n\t<span style=\"font-family:verdana,geneva,sans-serif\"><span style=\"font-size:14px\"><span style=\"color:#0000CD\"><strong>Construir uma zona de REAL CONFORTO n&atilde;o &eacute; para qualquer um.&nbsp;<\/strong><\/span>Demanda dedica&ccedil;&atilde;o, empenho.&nbsp;Visualize a&iacute; sua zona de real conforto particular. O que tem nela? Qual &eacute; o seu trabalho nesse cen&aacute;rio? Onde voc&ecirc; mora? O que voc&ecirc; faz no seu tempo livre? Quanto tempo livre voc&ecirc; tem? Como &eacute; sua casa, seu carro? Com quem voc&ecirc; convive? Como &eacute; sua rotina? Como voc&ecirc; se sente? Quanto voc&ecirc; cresce e aprende diariamente?&nbsp;O que voc&ecirc; precisa fazer para conseguir criar essa vida?<\/span><\/span>\n<\/p>\n<p style=\"text-align: justify\">\n\t&nbsp;\n<\/p>\n<p style=\"text-align: justify\">\n\t<span style=\"font-family:verdana,geneva,sans-serif\"><span style=\"font-size:14px\">Acho que muitos concurseiros colocam a foto do contracheque do cargo pretendido na mesa de estudos. Alguns colocam foto do carro dos sonhos, daqueeeela viagem, da casa. Mas isso &eacute; apenas uma partezinha do cen&aacute;rio. Um ornamento, digamos assim. <span style=\"color:#0000CD\"><strong>O mais importante &eacute; a SENSA&Ccedil;&Atilde;O.<\/strong><\/span> Feche os olhos e se coloque no cen&aacute;rio.&nbsp;Estude a sensa&ccedil;&atilde;o de ter aquela vida. <span style=\"color:#0000CD\"><strong>Mais do que qualquer coisa material ou frase de efeito, &Eacute; ISSO QUE VAI TE MOTIVAR.<\/strong><\/span><\/span><\/span>\n<\/p>\n<p style=\"text-align: justify\">\n\t&nbsp;\n<\/p>\n<p style=\"text-align: justify\">\n\t<span style=\"font-family:verdana,geneva,sans-serif\"><span style=\"font-size:14px\">Voc&ecirc; n&atilde;o estuda para ter casa, carro, viagem, roupas, restaurante chique.&nbsp;VOC&Ecirc; ESTUDA PARA SER MAIS FELIZ DO QUE &Eacute; HOJE.&nbsp;Casa, carro, viagem, roupas e restaurante chique S&Atilde;O MEIOS. A FELICIDADE &eacute; o fim pretendido.<\/span><\/span>\n<\/p>\n<p style=\"text-align: justify\">\n\t&nbsp;\n<\/p>\n<p style=\"text-align: justify\">\n\t<span style=\"font-family:verdana,geneva,sans-serif\"><span style=\"font-size:14px\">Partiu estudar! Partiu ZONA DE REAL CONFORTO!<\/span><\/span>\n<\/p>\n<p style=\"text-align: justify\">\n\t&nbsp;\n<\/p>\n<p style=\"text-align: justify\">\n\t&nbsp;\n<\/p>\n<p>\n\tBons estudos!\n<\/p>\n<p>\n\tGabi\n<\/p>\n<p>\n\t<strong><u><a href=\"https:\/\/www.estrategiaconcursos.com.br\/cursosPorConcurso\/coaching-382\/\">Coach<\/a><\/u><\/strong><a href=\"https:\/\/www.estrategiaconcursos.com.br\/cursosPorConcurso\/coaching-382\/\"><strong><u>&nbsp;Estrat&eacute;gia Concursos<\/u><\/strong><\/a>\n<\/p>\n<p>\n\t<strong>&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8211;<\/strong>\n<\/p>\n<p>\n\t<strong>AVISO:<\/strong>\n<\/p>\n<p>\n\t<strong>1 &#8211; Os artigos ser&atilde;o postados TODA TER&Ccedil;A!&nbsp;<\/strong>\n<\/p>\n<p>\n\t&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;-\n<\/p>\n<p>\n\tCurtiu o artigo? Comente a&iacute; embaixo! Quer sugerir tema de artigo? Fique &agrave; vontade!\n<\/p>\n<p>\n\tJ&aacute; me acompanha nas redes sociais? T&ocirc; te esperando l&aacute;!\n<\/p>\n<p>\n\t<strong>Quer ser meu coachee?<\/strong>&nbsp;&Eacute; s&oacute; avisar a equipe do Estrat&eacute;gia quando fizer a matr&iacute;cula! :)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A zona de conforto &eacute; MARAVILHOSA! Pronto, falei. &nbsp; Estou em crise existencial com frases de efeito.&nbsp;E olha que sempre as curti bastante. Mas a motiva&ccedil;&atilde;o proveniente delas &eacute; muito fugaz. E sabe por qu&ecirc;?&nbsp;Porque elas n&atilde;o s&atilde;o precisas.&nbsp;As palavras, na minha humilde opini&atilde;o, s&atilde;o mal escolhidas. E voc&ecirc;, ser pensante, mais cedo ou mais [&hellip;]<\/p>\n","protected":false},"author":423,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"post_tipo":"article","footnotes":""},"categories":[1],"tags":[],"tax_estado":[],"class_list":["post-70305","post","type-post","status-publish","format-standard","hentry","category-cursos-e-concursos"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.2 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Zona de DESconforto<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/zona-de-desconforto\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Zona de DESconforto\" \/>\n<meta property=\"og:description\" content=\"A zona de conforto &eacute; MARAVILHOSA! Pronto, falei. &nbsp; Estou em crise existencial com frases de efeito.&nbsp;E olha que sempre as curti bastante. Mas a motiva&ccedil;&atilde;o proveniente delas &eacute; muito fugaz. E sabe por qu&ecirc;?&nbsp;Porque elas n&atilde;o s&atilde;o precisas.&nbsp;As palavras, na minha humilde opini&atilde;o, s&atilde;o mal escolhidas. E voc&ecirc;, ser pensante, mais cedo ou mais [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/zona-de-desconforto\/\" \/>\n<meta property=\"og:site_name\" content=\"Estrat\u00e9gia Concursos\" \/>\n<meta property=\"article:published_time\" content=\"2017-04-11T12:14:08+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-05-10T13:11:36+00:00\" \/>\n<meta name=\"author\" content=\"Gabriela Knoblauch\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:site\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gabriela Knoblauch\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/zona-de-desconforto\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/zona-de-desconforto\/\"},\"author\":{\"name\":\"Gabriela Knoblauch\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/622d93253cb9ef3af014a0ce658d184a\"},\"headline\":\"Zona de DESconforto\",\"datePublished\":\"2017-04-11T12:14:08+00:00\",\"dateModified\":\"2017-05-10T13:11:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/zona-de-desconforto\/\"},\"wordCount\":896,\"commentCount\":28,\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"articleSection\":[\"Concursos P\u00fablicos\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/zona-de-desconforto\/#respond\"]}],\"copyrightYear\":\"2017\",\"copyrightHolder\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/zona-de-desconforto\/\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/zona-de-desconforto\/\",\"name\":\"Zona de DESconforto\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\"},\"datePublished\":\"2017-04-11T12:14:08+00:00\",\"dateModified\":\"2017-05-10T13:11:36+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/zona-de-desconforto\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/zona-de-desconforto\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/zona-de-desconforto\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Zona de DESconforto\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"name\":\"Estrat\u00e9gia Concursos\",\"description\":\"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.\",\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\",\"name\":\"Estrat\u00e9gia Concursos\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"width\":230,\"height\":60,\"caption\":\"Estrat\u00e9gia Concursos\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/EstratConcursos\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/622d93253cb9ef3af014a0ce658d184a\",\"name\":\"Gabriela Knoblauch\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/d26c5a121c8db2de08ffbc428752dadaae2055eefb797f261688ca1ac09b241f?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/d26c5a121c8db2de08ffbc428752dadaae2055eefb797f261688ca1ac09b241f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/d26c5a121c8db2de08ffbc428752dadaae2055eefb797f261688ca1ac09b241f?s=96&d=mm&r=g\",\"caption\":\"Gabriela Knoblauch\"},\"description\":\"Acredito no poder da persist\u00eancia e na import\u00e2ncia da estrat\u00e9gia nos estudos para acelerar a aprova\u00e7\u00e3o. No meu curso de Coaching trabalho em 2 frentes: 1 - T\u00e9cnicas de estudo 2 - Intelig\u00eancia emocional para concursos Entendo que ambas s\u00e3o fundamentais para obter um resultado excelente em qualquer certame. Toda ter\u00e7a posto artigo no site sobre os temas citados. N\u00e3o perca! :)\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/gabrielaknobluachestrategiaconcursos-com-br\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Zona de DESconforto","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.estrategiaconcursos.com.br\/blog\/zona-de-desconforto\/","og_locale":"pt_BR","og_type":"article","og_title":"Zona de DESconforto","og_description":"A zona de conforto &eacute; MARAVILHOSA! Pronto, falei. &nbsp; Estou em crise existencial com frases de efeito.&nbsp;E olha que sempre as curti bastante. Mas a motiva&ccedil;&atilde;o proveniente delas &eacute; muito fugaz. E sabe por qu&ecirc;?&nbsp;Porque elas n&atilde;o s&atilde;o precisas.&nbsp;As palavras, na minha humilde opini&atilde;o, s&atilde;o mal escolhidas. E voc&ecirc;, ser pensante, mais cedo ou mais [&hellip;]","og_url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/zona-de-desconforto\/","og_site_name":"Estrat\u00e9gia Concursos","article_published_time":"2017-04-11T12:14:08+00:00","article_modified_time":"2017-05-10T13:11:36+00:00","author":"Gabriela Knoblauch","twitter_card":"summary_large_image","twitter_creator":"@EstratConcursos","twitter_site":"@EstratConcursos","twitter_misc":{"Escrito por":"Gabriela Knoblauch","Est. tempo de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/zona-de-desconforto\/#article","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/zona-de-desconforto\/"},"author":{"name":"Gabriela Knoblauch","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/622d93253cb9ef3af014a0ce658d184a"},"headline":"Zona de DESconforto","datePublished":"2017-04-11T12:14:08+00:00","dateModified":"2017-05-10T13:11:36+00:00","mainEntityOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/zona-de-desconforto\/"},"wordCount":896,"commentCount":28,"publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"articleSection":["Concursos P\u00fablicos"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/zona-de-desconforto\/#respond"]}],"copyrightYear":"2017","copyrightHolder":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/zona-de-desconforto\/","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/zona-de-desconforto\/","name":"Zona de DESconforto","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website"},"datePublished":"2017-04-11T12:14:08+00:00","dateModified":"2017-05-10T13:11:36+00:00","breadcrumb":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/zona-de-desconforto\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/zona-de-desconforto\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/zona-de-desconforto\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.estrategiaconcursos.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Zona de DESconforto"}]},{"@type":"WebSite","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","name":"Estrat\u00e9gia Concursos","description":"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.","publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization","name":"Estrat\u00e9gia Concursos","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","width":230,"height":60,"caption":"Estrat\u00e9gia Concursos"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/EstratConcursos"]},{"@type":"Person","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/622d93253cb9ef3af014a0ce658d184a","name":"Gabriela Knoblauch","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/d26c5a121c8db2de08ffbc428752dadaae2055eefb797f261688ca1ac09b241f?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/d26c5a121c8db2de08ffbc428752dadaae2055eefb797f261688ca1ac09b241f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d26c5a121c8db2de08ffbc428752dadaae2055eefb797f261688ca1ac09b241f?s=96&d=mm&r=g","caption":"Gabriela Knoblauch"},"description":"Acredito no poder da persist\u00eancia e na import\u00e2ncia da estrat\u00e9gia nos estudos para acelerar a aprova\u00e7\u00e3o. No meu curso de Coaching trabalho em 2 frentes: 1 - T\u00e9cnicas de estudo 2 - Intelig\u00eancia emocional para concursos Entendo que ambas s\u00e3o fundamentais para obter um resultado excelente em qualquer certame. Toda ter\u00e7a posto artigo no site sobre os temas citados. N\u00e3o perca! :)","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/gabrielaknobluachestrategiaconcursos-com-br\/"}]}},"_links":{"self":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/70305","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/users\/423"}],"replies":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/comments?post=70305"}],"version-history":[{"count":1,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/70305\/revisions"}],"predecessor-version":[{"id":70307,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/70305\/revisions\/70307"}],"wp:attachment":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media?parent=70305"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/categories?post=70305"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tags?post=70305"},{"taxonomy":"tax_estado","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tax_estado?post=70305"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}