{"id":687421,"date":"2021-03-08T11:14:09","date_gmt":"2021-03-08T14:14:09","guid":{"rendered":"https:\/\/blog-estrategia.mystagingwebsite.com\/blog\/?p=687421"},"modified":"2021-03-08T11:20:51","modified_gmt":"2021-03-08T14:20:51","slug":"juiz-ms-resultado-da-prova-de-sentenca","status":"publish","type":"post","link":"https:\/\/www.estrategiaconcursos.com.br\/blog\/juiz-ms-resultado-da-prova-de-sentenca\/","title":{"rendered":"Juiz  TJ MS: confira aqui o resultado da prova de senten\u00e7a!"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\" id=\"h-sal-rio-inicial-de-r-27-363-98\">Sal\u00e1rio inicial de R$ 27.363,98<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Saiu nesta segunda-feira, 08 de mar\u00e7o de 2021, o resultado da prova de senten\u00e7a do concurso Juiz MS. Nas provas de senten\u00e7a, os candidatos tiveram que elaborar&nbsp;<strong>duas senten\u00e7as<\/strong>, uma c\u00edvel e outra criminal.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para ser aprovado nesta etapa foi necess\u00e1rio alcan\u00e7ar pelo menos 6 pontos (de um total de 10) em cada uma das provas. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De acordo com o \u00f3rg\u00e3o, todos os candidatos que realizaram a Prova de Senten\u00e7a poder\u00e3o visualizar as suas notas e conferir os seus desempenhos individuais por interm\u00e9dio do site da Funda\u00e7\u00e3o Carlos Chagas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Veja no link abaixo:<\/strong><\/p>\n\n\n\n<p class=\"has-text-align-center has-light-green-cyan-background-color has-background wp-block-paragraph\"><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-content\/uploads\/2021\/03\/tj-ms-juiz-prova-de-sentenca-1.pdf\"><strong>Resultado da prova de senten\u00e7a<\/strong><\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">S\u00e3o ofertadas no concurso&nbsp;<strong>10 vagas<\/strong>&nbsp;para o cargo de Juiz Substituto. A remunera\u00e7\u00e3o \u00e9 de R$ 27.363,98. Para ingressar na Magistratura \u00e9 necess\u00e1rio ser bacharel em Direito e contar, at\u00e9 a fase de inscri\u00e7\u00e3o definitiva, com&nbsp;<strong>tr\u00eas&nbsp;anos&nbsp;<\/strong>de atividade jur\u00eddica.<\/p>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\"><strong>Quer saber mais sobre o concurso Juiz MS? Clique no link abaixo e fique por dentro de todas as informa\u00e7\u00f5es!<\/strong><\/p>\n\n\n\n<p class=\"has-text-align-center has-luminous-vivid-amber-background-color has-background wp-block-paragraph\"><strong>Saiba mais:<a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-magistratura-ms\/\"> Concurso Magistratura MS<\/a><\/strong><\/p>\n\n\n\n<p class=\"has-text-align-center has-pale-cyan-blue-background-color has-background wp-block-paragraph\"><a href=\"https:\/\/www.youtube.com\/channel\/UClbMGuYbj2Mh1m3w144ETWQ\"><strong>Youtube &#8211; Estrat\u00e9gia Carreiras Jur\u00eddicas <\/strong><\/a><\/p>\n\n\n\n<h2 class=\"has-text-align-center wp-block-heading\" id=\"cursos\">Prepare-se para o concurso JUIZ MS<\/h2>\n\n\n\n<div class=\"container\" id=\"boxes\">\n  <div class=\"row\">\n\n    <div class=\"col-sm\">\n      <div class=\"banner-ecj\" id=\"box-assinatura\">\n        <h3 class=\"titulo-assinatura\">Curso para Concurso Magistratura MS <\/h3>\n        <p class=\"subtitulo-assinatura\">Cursos focados no edital do concurso<\/p>\n        <div class=\"box-botao\">\n          <a class=\"btn-assinatura\" target=\"_blank\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/cursosPorConcurso\/tj-ms-tribunal-de-justica-do-mato-grosso-do-sul-juiz-substituto\/\" role=\"button\" rel=\"noopener noreferrer\">Conhe\u00e7a mais<\/a>\n        <\/div>\n      <\/div>\n      <p class=\"texto-auxiliar\">Prepare-se com o melhor material e com quem mais aprova em concursos em todo o pa\u00eds. \n<\/p>\n    <\/div>\n\n  <\/div>\n<\/div>\n\n\n\n<div class=\"container\" id=\"boxes\">\n  <div class=\"row\">\n\n    <div class=\"col-sm\">\n      <div class=\"banner-ecj\" id=\"box-assinatura\">\n        <h3 class=\"titulo-assinatura\">Assinatura Jur\u00eddica <\/h3>\n        <p class=\"subtitulo-assinatura\">Conhe\u00e7a os planos<\/p>\n        <div class=\"box-botao\">\n          <a class=\"btn-assinatura\" target=\"_blank\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/assinaturas-ecj\/\" role=\"button\" rel=\"noopener noreferrer\">Conhe\u00e7a mais<\/a>\n        <\/div>\n      <\/div>\n      <p class=\"texto-auxiliar\">Prepare-se com o melhor material e com quem mais aprova em Concursos P\u00fablicos em todo o pa\u00eds. \n<\/p>\n    <\/div>\n\n  <\/div>\n<\/div>\n\n\n\n<div class=\"container\" id=\"boxes\">\n  <div class=\"row\">\n\n    <div class=\"col-sm\" id=\"boxes-concursos\">\n      <div style=\"background-color: #005DAD;\" class=\"conteudo-concursos\" id=\"box-concursos\">\n        <h3 class=\"titulo-assinatura\">Concursos Abertos<\/h3>\n        <p class=\"subtitulo-assinatura\">mais de 15 mil vagas<\/p>\n        <div class=\"box-botao\">\n          <a class=\"btn-assinatura\" target=\"_blank\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-abertos\/\" role=\"button\" rel=\"noopener noreferrer\">Conhe\u00e7a Agora<\/a>\n        <\/div>\n      <\/div>\n    <\/div>\n\n    <div class=\"col-sm\" id=\"boxes-concursos\">\n      <div style=\"background-color: #419FF0;\" class=\"conteudo-concursos\" id=\"box-concursos\">\n        <h3 class=\"titulo-assinatura\">Concursos 2021<\/h3>\n        <p class=\"subtitulo-assinatura\">mais de 17 mil vagas<\/p>\n        <div class=\"box-botao\">\n          <a class=\"btn-assinatura\" target=\"_blank\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-2021\/\" role=\"button\" rel=\"noopener noreferrer\">Conhe\u00e7a Agora<\/a>\n        <\/div>\n      <\/div>\n    <\/div>\n\n<div class=\"col-sm\" id=\"boxes-concursos\">\n      <div style=\"background-color: #1A7ED5;\" class=\"conteudo-concursos\" id=\"box-concursos\">\n        <h3 class=\"titulo-assinatura\">Concursos de Direito<\/h3>\n        <p class=\"subtitulo-assinatura\">Vagas para a \u00e1rea jur\u00eddica<\/p>\n        <div class=\"box-botao\">\n          <a class=\"btn-assinatura\" target=\"_blank\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-de-direito\/\" role=\"button\" rel=\"noopener noreferrer\">Conhe\u00e7a Agora<\/a>\n        <\/div>\n      <\/div>\n    <\/div>\n\n  <\/div>\n<\/div>\n\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"102\" src=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-content\/uploads\/2017\/03\/coruja-ficha-tecnica-300x102.png\" alt=\"Ficha t\u00e9cnica \" class=\"wp-image-68542\"\/><\/figure>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"ficha\"><strong>Informa\u00e7\u00f5es sobre o concurso Magistratura MS<\/strong><\/h4>\n\n\n\n<p class=\"wp-block-paragraph\"><br \/>\u25ba<strong>Vagas<\/strong>: 10 vagas<br \/>\u25ba<strong>Cargos<\/strong>: Juiz de Direito Substituto<br \/>\u25ba<strong>Lota\u00e7\u00f5es<\/strong>: Mato Grosso do Sul<br \/>\u25ba<strong>Banca<\/strong>: FCC<br \/>\u25ba<strong>Escolaridade<\/strong>: Bacharelado em Direito + 3 anos de atividade jur\u00eddica<br \/>\u25ba<strong>Edital<\/strong>:&nbsp;<a rel=\"noreferrer noopener\" href=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2019\/11\/01080713\/Edital-TJ-MS-Juiz-Substituto-2019.pdf\" target=\"_blank\">2019<\/a><br \/><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-content\/uploads\/2020\/03\/retificacao_magis-MS.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">Retifica\u00e7\u00e3o<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sal\u00e1rio inicial de R$ 27.363,98 Saiu nesta segunda-feira, 08 de mar\u00e7o de 2021, o resultado da prova de senten\u00e7a do concurso Juiz MS. Nas provas de senten\u00e7a, os candidatos tiveram que elaborar&nbsp;duas senten\u00e7as, uma c\u00edvel e outra criminal. Para ser aprovado nesta etapa foi necess\u00e1rio alcan\u00e7ar pelo menos 6 pontos (de um total de 10) [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":417449,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"post_tipo":"news","footnotes":""},"categories":[2185],"tags":[],"tax_estado":[219975],"class_list":["post-687421","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-carreiras-juridicas","tax_estado-ms"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Juiz TJ MS: confira aqui o resultado da prova de senten\u00e7a!<\/title>\n<meta name=\"description\" content=\"Foi publicado o resultado da prova de senten\u00e7a do concurso Juiz MS. Confira neste artigo a lista completa e veja mais informa\u00e7\u00f5es.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/juiz-ms-resultado-da-prova-de-sentenca\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Juiz TJ MS: confira aqui o resultado da prova de senten\u00e7a!\" \/>\n<meta property=\"og:description\" content=\"Foi publicado o resultado da prova de senten\u00e7a do concurso Juiz MS. Confira neste artigo a lista completa e veja mais informa\u00e7\u00f5es.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/juiz-ms-resultado-da-prova-de-sentenca\/\" \/>\n<meta property=\"og:site_name\" content=\"Estrat\u00e9gia Concursos\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/EstrategiaConcursos\" \/>\n<meta property=\"article:published_time\" content=\"2021-03-08T14:14:09+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-03-08T14:20:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2019\/09\/06130357\/Magistratura-MS.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"628\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Coordena\u00e7\u00e3o\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:site\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Coordena\u00e7\u00e3o\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/juiz-ms-resultado-da-prova-de-sentenca\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/juiz-ms-resultado-da-prova-de-sentenca\\\/\"},\"author\":{\"name\":\"Coordena\u00e7\u00e3o\",\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/#\\\/schema\\\/person\\\/b4a388c97673c5f483d72185668afa1f\"},\"headline\":\"Juiz TJ MS: confira aqui o resultado da prova de senten\u00e7a!\",\"datePublished\":\"2021-03-08T14:14:09+00:00\",\"dateModified\":\"2021-03-08T14:20:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/juiz-ms-resultado-da-prova-de-sentenca\\\/\"},\"wordCount\":337,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/juiz-ms-resultado-da-prova-de-sentenca\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dhg1h5j42swfq.cloudfront.net\\\/2019\\\/09\\\/06130357\\\/Magistratura-MS.jpg\",\"articleSection\":[\"Jur\u00eddico\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/juiz-ms-resultado-da-prova-de-sentenca\\\/#respond\"]}],\"copyrightYear\":\"2021\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/juiz-ms-resultado-da-prova-de-sentenca\\\/\",\"url\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/juiz-ms-resultado-da-prova-de-sentenca\\\/\",\"name\":\"Juiz TJ MS: confira aqui o resultado da prova de senten\u00e7a!\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/juiz-ms-resultado-da-prova-de-sentenca\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/juiz-ms-resultado-da-prova-de-sentenca\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dhg1h5j42swfq.cloudfront.net\\\/2019\\\/09\\\/06130357\\\/Magistratura-MS.jpg\",\"datePublished\":\"2021-03-08T14:14:09+00:00\",\"dateModified\":\"2021-03-08T14:20:51+00:00\",\"description\":\"Foi publicado o resultado da prova de senten\u00e7a do concurso Juiz MS. Confira neste artigo a lista completa e veja mais informa\u00e7\u00f5es.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/juiz-ms-resultado-da-prova-de-sentenca\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/juiz-ms-resultado-da-prova-de-sentenca\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/juiz-ms-resultado-da-prova-de-sentenca\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dhg1h5j42swfq.cloudfront.net\\\/2019\\\/09\\\/06130357\\\/Magistratura-MS.jpg\",\"contentUrl\":\"https:\\\/\\\/dhg1h5j42swfq.cloudfront.net\\\/2019\\\/09\\\/06130357\\\/Magistratura-MS.jpg\",\"width\":1200,\"height\":628,\"caption\":\"concurso magistratura ms\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/juiz-ms-resultado-da-prova-de-sentenca\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Juiz TJ MS: confira aqui o resultado da prova de senten\u00e7a!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/\",\"name\":\"Estrat\u00e9gia Concursos\",\"description\":\"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/#organization\",\"name\":\"Estrat\u00e9gia Concursos\",\"url\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dhg1h5j42swfq.cloudfront.net\\\/2025\\\/06\\\/03203428\\\/logo_concursos-1.jpg\",\"contentUrl\":\"https:\\\/\\\/dhg1h5j42swfq.cloudfront.net\\\/2025\\\/06\\\/03203428\\\/logo_concursos-1.jpg\",\"width\":230,\"height\":60,\"caption\":\"Estrat\u00e9gia Concursos\"},\"image\":{\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/EstratConcursos\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/#\\\/schema\\\/person\\\/b4a388c97673c5f483d72185668afa1f\",\"name\":\"Coordena\u00e7\u00e3o\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b720319e4c9a967eb58678d110f4fe35452fc5d5f97b202bac7b8acceb18c6ad?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b720319e4c9a967eb58678d110f4fe35452fc5d5f97b202bac7b8acceb18c6ad?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b720319e4c9a967eb58678d110f4fe35452fc5d5f97b202bac7b8acceb18c6ad?s=96&d=mm&r=g\",\"caption\":\"Coordena\u00e7\u00e3o\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/EstrategiaConcursos\",\"https:\\\/\\\/x.com\\\/EstratConcursos\"],\"url\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/author\\\/estrategia2013\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Juiz TJ MS: confira aqui o resultado da prova de senten\u00e7a!","description":"Foi publicado o resultado da prova de senten\u00e7a do concurso Juiz MS. Confira neste artigo a lista completa e veja mais informa\u00e7\u00f5es.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.estrategiaconcursos.com.br\/blog\/juiz-ms-resultado-da-prova-de-sentenca\/","og_locale":"pt_BR","og_type":"article","og_title":"Juiz TJ MS: confira aqui o resultado da prova de senten\u00e7a!","og_description":"Foi publicado o resultado da prova de senten\u00e7a do concurso Juiz MS. Confira neste artigo a lista completa e veja mais informa\u00e7\u00f5es.","og_url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/juiz-ms-resultado-da-prova-de-sentenca\/","og_site_name":"Estrat\u00e9gia Concursos","article_author":"https:\/\/www.facebook.com\/EstrategiaConcursos","article_published_time":"2021-03-08T14:14:09+00:00","article_modified_time":"2021-03-08T14:20:51+00:00","og_image":[{"width":1200,"height":628,"url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2019\/09\/06130357\/Magistratura-MS.jpg","type":"image\/jpeg"}],"author":"Coordena\u00e7\u00e3o","twitter_card":"summary_large_image","twitter_creator":"@EstratConcursos","twitter_site":"@EstratConcursos","twitter_misc":{"Escrito por":"Coordena\u00e7\u00e3o","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/juiz-ms-resultado-da-prova-de-sentenca\/#article","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/juiz-ms-resultado-da-prova-de-sentenca\/"},"author":{"name":"Coordena\u00e7\u00e3o","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/b4a388c97673c5f483d72185668afa1f"},"headline":"Juiz TJ MS: confira aqui o resultado da prova de senten\u00e7a!","datePublished":"2021-03-08T14:14:09+00:00","dateModified":"2021-03-08T14:20:51+00:00","mainEntityOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/juiz-ms-resultado-da-prova-de-sentenca\/"},"wordCount":337,"commentCount":0,"publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/juiz-ms-resultado-da-prova-de-sentenca\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2019\/09\/06130357\/Magistratura-MS.jpg","articleSection":["Jur\u00eddico"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/juiz-ms-resultado-da-prova-de-sentenca\/#respond"]}],"copyrightYear":"2021","copyrightHolder":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/juiz-ms-resultado-da-prova-de-sentenca\/","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/juiz-ms-resultado-da-prova-de-sentenca\/","name":"Juiz TJ MS: confira aqui o resultado da prova de senten\u00e7a!","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/juiz-ms-resultado-da-prova-de-sentenca\/#primaryimage"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/juiz-ms-resultado-da-prova-de-sentenca\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2019\/09\/06130357\/Magistratura-MS.jpg","datePublished":"2021-03-08T14:14:09+00:00","dateModified":"2021-03-08T14:20:51+00:00","description":"Foi publicado o resultado da prova de senten\u00e7a do concurso Juiz MS. Confira neste artigo a lista completa e veja mais informa\u00e7\u00f5es.","breadcrumb":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/juiz-ms-resultado-da-prova-de-sentenca\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/juiz-ms-resultado-da-prova-de-sentenca\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/juiz-ms-resultado-da-prova-de-sentenca\/#primaryimage","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2019\/09\/06130357\/Magistratura-MS.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2019\/09\/06130357\/Magistratura-MS.jpg","width":1200,"height":628,"caption":"concurso magistratura ms"},{"@type":"BreadcrumbList","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/juiz-ms-resultado-da-prova-de-sentenca\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.estrategiaconcursos.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Juiz TJ MS: confira aqui o resultado da prova de senten\u00e7a!"}]},{"@type":"WebSite","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","name":"Estrat\u00e9gia Concursos","description":"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.","publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization","name":"Estrat\u00e9gia Concursos","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","width":230,"height":60,"caption":"Estrat\u00e9gia Concursos"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/EstratConcursos"]},{"@type":"Person","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/b4a388c97673c5f483d72185668afa1f","name":"Coordena\u00e7\u00e3o","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/b720319e4c9a967eb58678d110f4fe35452fc5d5f97b202bac7b8acceb18c6ad?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b720319e4c9a967eb58678d110f4fe35452fc5d5f97b202bac7b8acceb18c6ad?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b720319e4c9a967eb58678d110f4fe35452fc5d5f97b202bac7b8acceb18c6ad?s=96&d=mm&r=g","caption":"Coordena\u00e7\u00e3o"},"sameAs":["https:\/\/www.facebook.com\/EstrategiaConcursos","https:\/\/x.com\/EstratConcursos"],"url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/estrategia2013\/"}]}},"_links":{"self":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/687421","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/comments?post=687421"}],"version-history":[{"count":0,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/687421\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media\/417449"}],"wp:attachment":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media?parent=687421"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/categories?post=687421"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tags?post=687421"},{"taxonomy":"tax_estado","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tax_estado?post=687421"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}