{"id":685885,"date":"2021-03-15T16:40:00","date_gmt":"2021-03-15T19:40:00","guid":{"rendered":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?p=685885"},"modified":"2021-03-11T16:40:35","modified_gmt":"2021-03-11T19:40:35","slug":"reta-final-direito-administrativo-para-pf","status":"publish","type":"post","link":"https:\/\/www.estrategiaconcursos.com.br\/blog\/reta-final-direito-administrativo-para-pf\/","title":{"rendered":"Resumo de direito administrativo para PF &#8211; Princ\u00edpios e Organiza\u00e7\u00e3o administrativa"},"content":{"rendered":"\n<p>Fala, pessoal. Ent\u00e3o, nesse artigo vamos fazer um resumo sobre os principais pontos de direito administrativo para a prova da PF. Conforme an\u00e1lise, verificamos que os temas de maiores relev\u00e2ncia s\u00e3o:<br \/> <br \/><\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"455\" height=\"145\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/03\/05112025\/temas-e-incidencia-pf-e-prf.png\" alt=\"Temas de direito administrativo para PF\" class=\"wp-image-685947\" srcset=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/03\/05112025\/temas-e-incidencia-pf-e-prf.png 455w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/03\/05112025\/temas-e-incidencia-pf-e-prf-300x96.png 300w\" sizes=\"auto, (max-width: 455px) 100vw, 455px\" \/><figcaption>Temas e incid\u00eancia de Direito administrativo para PF<\/figcaption><\/figure><\/div>\n\n\n\n<p>Dividiremos os assuntos em dois artigos para que sejam mais bem abordados. Na parte um falamos sobre os poderes administrativos e gente p\u00fablicos. E ent\u00e3o, na parte dois falaremos sobre princ\u00edpios impl\u00edcitos e expl\u00edcitos e organiza\u00e7\u00e3o administrativa. Entretanto, n\u00e3o temos como esgotar esses temas, por isso falaremos dos pontos mais importantes e mais cobrados. Vamos?<br \/><br \/><br \/><br \/><\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-terceiro-assunto-de-direito-administrativo-para-pf-princ-pios-da-administra-o-p-blica\"><br \/>Terceiro assunto de direito administrativo para PF:  Princ\u00edpios da administra\u00e7\u00e3o p\u00fablica<br \/><\/h2>\n\n\n\n<p>Os princ\u00edpios expressos s\u00e3o aqueles previstos na Constitui\u00e7\u00e3o Federal como:  legalidade, impessoalidade, moralidade, publicidade e efici\u00eancia. Enquanto os princ\u00edpios impl\u00edcitos n\u00e3o est\u00e3o previstos na constitui\u00e7\u00e3o. Mas, muitas vezes est\u00e3o previstos em legisla\u00e7\u00f5es.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-princ-pios-expressos\"><br \/><br \/>Princ\u00edpios expressos<br \/><\/h2>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-legalidade\"><br \/>Legalidade<\/h3>\n\n\n\n<p><br \/>Segundo Maria Sylvia Zanella Di Pietro, o princ\u00edpio da legalidade constitui uma das garantias principais de respeito aos direitos individuais. Isso ocorre porque a lei, ao mesmo tempo em que os define, estabelece tamb\u00e9m os limites de atua\u00e7\u00e3o administrativa que tenha por objeto a restri\u00e7\u00e3o ao exerc\u00edcio de tais direitos em benef\u00edcio da coletividade.<\/p>\n\n\n\n<p>Portanto, para os administrados, a legalidade significa que tudo o que n\u00e3o for proibido ser\u00e1 permitido. Por outro lado, para a administra\u00e7\u00e3o, s\u00f3 podem ser realizadas atividades previstas na legisla\u00e7\u00e3o.<\/p>\n\n\n\n<p>Contudo, n\u00e3o se deve confundir legalidade com reserva legal. Porque o primeiro significa que a atua\u00e7\u00e3o da administra\u00e7\u00e3o deve ser pautada por lei em sentido amplo (constitui\u00e7\u00e3o, leis, regulamentos, portarias e outras normas secund\u00e1rias), enquanto na reserva legal, a mat\u00e9ria deve ser regulada por lei em sentido estrito (lei ordin\u00e1ria e lei complementar).<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-impessoalidade\"><br \/><br \/>Impessoalidade<br \/><\/h3>\n\n\n\n<p><br \/>A impessoalidade pode ser definida em sentido amplo e sentido estrito, j\u00e1 que todo ato da Administra\u00e7\u00e3o deve ser praticado visando \u00e0 satisfa\u00e7\u00e3o do interesse p\u00fablico (sentido amplo) e \u00e0 finalidade espec\u00edfica que foi prevista em lei (sentido estrito).<\/p>\n\n\n\n<p><br \/>Por isso, o princ\u00edpio da impessoalidade se traduz na ideia de isonomia, j\u00e1 que a Administra\u00e7\u00e3o deve atender a todos os administrados sem discrimina\u00e7\u00f5es.<\/p>\n\n\n\n<p>Al\u00e9m disso, tamb\u00e9m faz parte do sentido de impessoalidade, a veda\u00e7\u00e3o de promo\u00e7\u00e3o pessoal. Ou seja, n\u00e3o poder\u00e1 ocorrer a promo\u00e7\u00e3o pessoal do agente p\u00fablico pelos atos realizados, os agentes devem atuar em nome do Estado.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-moralidade\"><br \/><br \/>Moralidade<br \/><\/h3>\n\n\n\n<p>O princ\u00edpio da moralidade significa que, al\u00e9m da legalidade, o administrador p\u00fablico deve subordinar-se \u00e0 moralidade administrativa, ou seja, aos preceitos \u00e9ticos.<\/p>\n\n\n\n<p>Percebe-se que, por esse princ\u00edpio, todos os atos da administra\u00e7\u00e3o p\u00fablica, inclusive as nomea\u00e7\u00f5es, devem ocorrer com base na moralidade.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-sumula-vinculante-13\">Sumula vinculante 13<\/h4>\n\n\n\n<p>Vale ressaltar a s\u00famula vinculante do STF: a nomea\u00e7\u00e3o de c\u00f4njuge, companheiro ou parente em linha reta, colateral ou por afinidade, at\u00e9 o terceiro grau, inclusive, da autoridade nomeante ou de servidor da mesma pessoa jur\u00eddica investido em cargo de dire\u00e7\u00e3o, chefia ou assessoramento, para o exerc\u00edcio de cargo em comiss\u00e3o ou de confian\u00e7a ou, ainda, de fun\u00e7\u00e3o gratificada na administra\u00e7\u00e3o p\u00fablica direta e indireta em qualquer dos Poderes da Uni\u00e3o, dos estados, do Distrito Federal e dos munic\u00edpios, compreendido o ajuste mediante designa\u00e7\u00f5es rec\u00edprocas, viola a Constitui\u00e7\u00e3o Federal.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-publicidade\"><br \/><br \/>Publicidade<\/h3>\n\n\n\n<p><br \/><br \/>A publicidade \u00e9 o princ\u00edpio que permite a transpar\u00eancia nas realiza\u00e7\u00f5es dos agentes p\u00fablicos. Por isso, pode ter como finalidade o conhecimento das atividades dos administrados e o controle pela popula\u00e7\u00e3o.<br \/><br \/>Ressalta-se que a publicidade \u00e9 a regra, mas n\u00e3o um dever absoluto. Por isso, com exce\u00e7\u00e3o dos dados pessoais que dizem respeito a intimidade, honra e imagem de pessoas, e das informa\u00e7\u00f5es sigilosas que sejam imprescind\u00edveis para a seguran\u00e7a do Estado, todas as demais informa\u00e7\u00f5es devem ser disponibilizadas, seja de forma p\u00fablica ou por requerimento (como peti\u00e7\u00f5es, por exemplo).<br \/><\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-efici-ncia\"><br \/>Efici\u00eancia<br \/><\/h3>\n\n\n\n<p><br \/>O princ\u00edpio da efici\u00eancia preza que a administra\u00e7\u00e3o p\u00fablica obtenha os melhores resultados na presta\u00e7\u00e3o dos servi\u00e7os p\u00fablicos com o menor custo poss\u00edvel, ou seja, ser mais assertiva nos seus atos. <\/p>\n\n\n\n<p>Todavia, isso n\u00e3o significa que o Estado pode se pautar nesse princ\u00edpio para realizar a\u00e7\u00f5es ilegais. Como, por exemplo, n\u00e3o se pode deixar de licitar com base no princ\u00edpio da efici\u00eancia. Portanto, os atos da administra\u00e7\u00e3o p\u00fablica devem ser legais, morais e eficientes. <br \/><\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-princ-pios-impl-citos\"><br \/><br \/>Princ\u00edpios impl\u00edcitos<br \/><\/h2>\n\n\n\n<p>Para continuar esse resumo de direito administrativo para PF, vamos ver alguns princ\u00edpios impl\u00edcitos. Apesar de termos outros princ\u00edpios, vamos citar apenas os principais.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-princ-pio-da-supremacia-do-interesse-p-blico\">Princ\u00edpio da Supremacia do interesse p\u00fablico<\/h3>\n\n\n\n<p><br \/>O princ\u00edpio da supremacia do interesse p\u00fablico \u00e9 um dos princ\u00edpios basilares da administra\u00e7\u00e3o p\u00fablica. J\u00e1 que a administra\u00e7\u00e3o deve atender aos interesses da coletividade, em uma situa\u00e7\u00e3o de conflito com interesse particular, o interesse da coletividade deve prevalecer.<br \/><br \/>Como a pr\u00f3pria Cespe j\u00e1 disse, por exemplo, a previs\u00e3o em lei de cl\u00e1usulas exorbitantes aplic\u00e1veis aos contratos administrativos decorre diretamente do princ\u00edpio da supremacia do interesse p\u00fablico. Ou seja, pelo fato de atender aos interesses da coletividade, a administra\u00e7\u00e3o pode ter cl\u00e1usulas nos contratos administrativos que n\u00e3o s\u00e3o comuns em contratos privados. <\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-princ-pio-da-indisponibilidade-do-interesse-p-blico\"><br \/>Princ\u00edpio da indisponibilidade do interesse p\u00fablico<\/h3>\n\n\n\n<p><br \/>Enquanto o princ\u00edpio da supremacia representa as prerrogativas, o princ\u00edpio da indisponibilidade do interesse p\u00fablico trata das sujei\u00e7\u00f5es administrativas. Ou seja, o princ\u00edpio da indisponibilidade do interesse p\u00fablico, s\u00e3o limita\u00e7\u00f5es impostas \u00e0 administra\u00e7\u00e3o para evitar o abuso ou les\u00e3o ao interesse p\u00fablico ou aos direitos fundamentais. <br \/><br \/>A Cespe, por exemplo, j\u00e1 afirmou que o administrador, quando gera a coisa p\u00fablica conforme o que na lei estiver determinado, ciente de que desempenha o papel de mero gestor de coisa que n\u00e3o \u00e9 sua, observa o princ\u00edpio da indisponibilidade do interesse p\u00fablico.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-outros-princ-pios-impl-citos\"><br \/><br \/>Outros princ\u00edpios impl\u00edcitos<\/h3>\n\n\n\n<p><br \/>J\u00e1 os princ\u00edpios da razoabilidade e da proporcionalidade exigem da administra\u00e7\u00e3o p\u00fablica a aplica\u00e7\u00e3o de limites e san\u00e7\u00f5es dentro do estritamente necess\u00e1rio para satisfazer ao interesse p\u00fablico. Ou seja, sem aplica\u00e7\u00e3o de san\u00e7\u00f5es ou restri\u00e7\u00f5es exageradas. <br \/><br \/>Por isso, a Cespe j\u00e1 afirmou que o princ\u00edpio da razoabilidade se apresenta como meio de controle da discricionariedade administrativa, e justifica a possibilidade de corre\u00e7\u00e3o judicial. Ou seja, nos atos discricion\u00e1rios, a razoabilidade e a proporcionalidades s\u00e3o importantes garantias para os administrados.<br \/><br \/>Outro princ\u00edpio impl\u00edcito da administra\u00e7\u00e3o p\u00fablica \u00e9 a autotutela. E o que significa esse princ\u00edpio? A Cespe j\u00e1 afirmou que decorre do princ\u00edpio de autotutela o poder da administra\u00e7\u00e3o p\u00fablica de rever os seus atos ilegais, independentemente de provoca\u00e7\u00e3o. Ou seja, a autotutela admite que a pr\u00f3pria administra\u00e7\u00e3o anule os atos ilegais e revogue os atos por motivo de conveni\u00eancia ou oportunidade. <br \/><br \/>E, por \u00faltimo, temos o princ\u00edpio da seguran\u00e7a jur\u00eddica, que a pr\u00f3pria Cespe j\u00e1 definiu que a seguran\u00e7a jur\u00eddica est\u00e1 em conferir certeza e estabilidade na rela\u00e7\u00e3o da administra\u00e7\u00e3o p\u00fablica com os administrados.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-resumo-dos-princ-pios\"><br \/><br \/>Resumo dos princ\u00edpios<\/h3>\n\n\n\n<p><br \/>Ent\u00e3o, vamos para um quadro resumo dos princ\u00edpios vistos aqui?<br \/><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"588\" height=\"325\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/03\/09094633\/resumo-dos-principios.png\" alt=\"Resumo de princ\u00edpios do direito administrativo para a PF\" class=\"wp-image-688523\" srcset=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/03\/09094633\/resumo-dos-principios.png 588w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/03\/09094633\/resumo-dos-principios-300x166.png 300w\" sizes=\"auto, (max-width: 588px) 100vw, 588px\" \/><figcaption>Resumo dos princ\u00edpios <\/figcaption><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-quarto-assunto-de-direito-administrativo-para-pf-organiza-o-da-administra-o-p-blica\"><br \/>Quarto assunto de direito administrativo para PF: Organiza\u00e7\u00e3o da administra\u00e7\u00e3o p\u00fablica<\/h2>\n\n\n\n<p><br \/>Para continuar o resumo de direito administrativo para PF, vamos ver sobre organiza\u00e7\u00e3o administrativa. <\/p>\n\n\n\n<p><br \/>As entidades pol\u00edticas recebem compet\u00eancias diretamente da constitui\u00e7\u00e3o federal para prestar servi\u00e7os p\u00fablicos e por isso exercem de forma centralizada as atividades. J\u00e1 as entidades administrativas, exercem de forma descentralizada. O que isso significa? A descentraliza\u00e7\u00e3o ocorre quando o Estado n\u00e3o executa o servi\u00e7o por meio da administra\u00e7\u00e3o direta.<\/p>\n\n\n\n<p>H\u00e1 tr\u00eas tipos de descentraliza\u00e7\u00e3o, mas a forma\u00e7\u00e3o das entidades \u00e9 pela descentraliza\u00e7\u00e3o por outorga. A descentraliza\u00e7\u00e3o por outorga, tamb\u00e9m chamada de t\u00e9cnica ou funcional ou por servi\u00e7os, ocorre quando o Estado cria uma entidade com personalidade jur\u00eddica pr\u00f3pria e transfere a titularidade da execu\u00e7\u00e3o de determinado servi\u00e7o p\u00fablico. Logo, pressup\u00f5e para cria\u00e7\u00e3o da entidade, elabora\u00e7\u00e3o de lei ou autoriza\u00e7\u00e3o por meio de lei.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-resumo-de-descentraliza-o-e-desconcentra-o\">Resumo de descentraliza\u00e7\u00e3o e desconcentra\u00e7\u00e3o<\/h3>\n\n\n\n<p>Ent\u00e3o, vamos entender melhor isso?<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"591\" height=\"149\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/03\/09115712\/desconcentracao-e-descentralizacao.png\" alt=\"Desconcentra\u00e7\u00e3o e Descentraliza\u00e7\u00e3o\" class=\"wp-image-688775\" srcset=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/03\/09115712\/desconcentracao-e-descentralizacao.png 591w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/03\/09115712\/desconcentracao-e-descentralizacao-300x76.png 300w\" sizes=\"auto, (max-width: 591px) 100vw, 591px\" \/><figcaption>Desconcentra\u00e7\u00e3o e Descentraliza\u00e7\u00e3o<\/figcaption><\/figure>\n\n\n\n<p><br \/>J\u00e1 sabendo desses conceitos iniciais, vamos revisar t\u00f3picos mais espec\u00edficos da organiza\u00e7\u00e3o da administra\u00e7\u00e3o indireta?<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-administra-o-indireta\"><br \/><br \/>Administra\u00e7\u00e3o indireta<\/h3>\n\n\n\n<p>O principal t\u00f3pico de organiza\u00e7\u00e3o administrativa para a prova de direito administrativo da PF \u00e9 a administra\u00e7\u00e3o indireta.<br \/><br \/>A administra\u00e7\u00e3o p\u00fablica \u00e9 composta pela administra\u00e7\u00e3o p\u00fablica direta e administra\u00e7\u00e3o p\u00fablica indireta. A primeira \u00e9 um conjunto de \u00f3rg\u00e3os que integram as pessoas p\u00fablicas do Estado e que as compet\u00eancias s\u00e3o atribu\u00eddas de forma centralizada. <\/p>\n\n\n\n<p>J\u00e1 a administra\u00e7\u00e3o p\u00fablica indireta \u00e9 composta por entidades administrativas, que possuem personalidade jur\u00eddica pr\u00f3pria, e de forma vinculada a administra\u00e7\u00e3o p\u00fablica direta exerce atividades de forma descentralizada.<br \/><br \/>S\u00e3o tipos de administra\u00e7\u00e3o indireta as: autarquias, funda\u00e7\u00f5es, empresas p\u00fablicas e sociedades de economia mista.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-autarquia\"><br \/><br \/>Autarquia<br \/><\/h3>\n\n\n\n<p><br \/>S\u00e3o pessoas jur\u00eddicas p\u00fablicas, criadas por lei, com capacidade de desempenhar atividades que sejam pr\u00f3prias do Estado. Elas representam uma extens\u00e3o da administra\u00e7\u00e3o direta, j\u00e1 que desempenham um servi\u00e7o retirado da administra\u00e7\u00e3o direta. Por\u00e9m, com mais especializa\u00e7\u00e3o e mais autonomia do que o poder central.<br \/><\/p>\n\n\n\n<p>Como as autarquias agem conforme a administra\u00e7\u00e3o p\u00fablica central, gozam das mesmas prorrogativas e restri\u00e7\u00f5es. Mas como possuem personalidade jur\u00eddica pr\u00f3pria, os direitos e obriga\u00e7\u00f5es s\u00e3o em seu pr\u00f3prio nome.<\/p>\n\n\n\n<p>As autarquias est\u00e3o sujeitas a controle da pessoa pol\u00edtica que as criou, \u00e0s quais s\u00e3o vinculadas. Essa vincula\u00e7\u00e3o \u00e9 chamada de controle final\u00edstico ou de tutela, que s\u00e3o exercidos nos termos e nos limites da lei, j\u00e1 que n\u00e3o h\u00e1 hierarquia.<\/p>\n\n\n\n<p><br \/><\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-funda-es\"><br \/>Funda\u00e7\u00f5es<\/h3>\n\n\n\n<p><br \/><br \/><br \/>As funda\u00e7\u00f5es s\u00e3o definidas como a personifica\u00e7\u00e3o do patrim\u00f4nio ao qual \u00e9 atribu\u00edda uma finalidade social n\u00e3o lucrativa. Por isso, s\u00e3o destinadas a realizar atividades de interesse social, como educa\u00e7\u00e3o, sa\u00fade, pesquisa cientificas, entre outras. Cabe ressaltar que, cabe a Lei Complementar definir as \u00e1reas de atua\u00e7\u00e3o das funda\u00e7\u00f5es.<br \/><\/p>\n\n\n\n<p>Elas t\u00eam personalidade jur\u00eddica pr\u00f3pria, podendo ser p\u00fablica ou privada. A jurisprud\u00eancia e a doutrina admitem a cria\u00e7\u00e3o de funda\u00e7\u00f5es p\u00fablicas de direito p\u00fablico, criadas por lei e com regime de autarquia, e de funda\u00e7\u00f5es de direito privado que ter\u00e3o regime jur\u00eddico h\u00edbrido, com autoriza\u00e7\u00e3o legislativa para cria\u00e7\u00e3o.<\/p>\n\n\n\n<p>Por serem diferentes, as funda\u00e7\u00f5es p\u00fablicas possuem benef\u00edcios diferentes. As funda\u00e7\u00f5es p\u00fablicas de direito p\u00fablica possuem imunidade tribut\u00e1ria, prerrogativas processuais dos prazos em dobro para as manifesta\u00e7\u00f5es e duplo grau de jurisdi\u00e7\u00e3o e a possibilidade do uso de precat\u00f3rio. J\u00e1 as funda\u00e7\u00f5es de direito privado apenas possuem a imunidade tribut\u00e1ria.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-empresa-p-blica-e-sociedade-de-economia-mista\"><br \/><br \/>Empresa P\u00fablica e Sociedade de Economia Mista<\/h3>\n\n\n\n<p><br \/>Empresas P\u00fablicas e Sociedades de Economia Mista s\u00e3o pessoas jur\u00eddicas de direito privado, criadas por autoriza\u00e7\u00e3o legal, adequada a sua finalidade, para que seja exercida atividades gerais de car\u00e1ter econ\u00f4mico ou em certas situa\u00e7\u00f5es a presta\u00e7\u00e3o de servi\u00e7o p\u00fablico.<br \/><\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"443\" height=\"238\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/12\/16165043\/organizacao-da-administracao-indireta-semelhancas-entre-ep-e-sem.png\" alt=\"Semelhan\u00e7as entre EP e SEM\" class=\"wp-image-632410\" srcset=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/12\/16165043\/organizacao-da-administracao-indireta-semelhancas-entre-ep-e-sem.png 443w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/12\/16165043\/organizacao-da-administracao-indireta-semelhancas-entre-ep-e-sem-300x161.png 300w\" sizes=\"auto, (max-width: 443px) 100vw, 443px\" \/><figcaption>Semelhan\u00e7as entre EP e SEM<\/figcaption><\/figure><\/div>\n\n\n\n<p>Geralmente tamb\u00e9m n\u00e3o gozam de privil\u00e9gios fiscais, j\u00e1 que as empresas p\u00fablicas e as sociedades de economia mista n\u00e3o poder\u00e3o gozar de privil\u00e9gios fiscais n\u00e3o extensivos \u00e0s do setor privado. Em contraponto, quando prestarem servi\u00e7os p\u00fablicos subordinam-se predominantemente a regras de direito p\u00fablico.<\/p>\n\n\n\n<p>E quais s\u00e3o as diferen\u00e7as entre as duas empresas? <\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"848\" height=\"173\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/12\/16165303\/organizacao-da-administracao-indireta-diferencas-entre-ep-e-sem.png\" alt=\"Diferen\u00e7as entre EP e SEM\" class=\"wp-image-632412\" srcset=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/12\/16165303\/organizacao-da-administracao-indireta-diferencas-entre-ep-e-sem.png 848w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/12\/16165303\/organizacao-da-administracao-indireta-diferencas-entre-ep-e-sem-300x61.png 300w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/12\/16165303\/organizacao-da-administracao-indireta-diferencas-entre-ep-e-sem-768x157.png 768w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/12\/16165303\/organizacao-da-administracao-indireta-diferencas-entre-ep-e-sem-610x124.png 610w\" sizes=\"auto, (max-width: 848px) 100vw, 848px\" \/><figcaption>Diferen\u00e7as entre EP e SEM<\/figcaption><\/figure>\n\n\n\n<p><br \/><\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-resumo-da-organiza-o-da-administra-o-indireta\">Resumo da organiza\u00e7\u00e3o da administra\u00e7\u00e3o indireta<br \/><\/h2>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"894\" height=\"305\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/12\/20153026\/organizacao-da-administracao-indireta-compilado-das-entidades-1.png\" alt=\"Resumo de administra\u00e7\u00e3o indireta para prova de direito administrativo da PF\" class=\"wp-image-634654\" srcset=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/12\/20153026\/organizacao-da-administracao-indireta-compilado-das-entidades-1.png 894w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/12\/20153026\/organizacao-da-administracao-indireta-compilado-das-entidades-1-300x102.png 300w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/12\/20153026\/organizacao-da-administracao-indireta-compilado-das-entidades-1-768x262.png 768w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/12\/20153026\/organizacao-da-administracao-indireta-compilado-das-entidades-1-610x208.png 610w\" sizes=\"auto, (max-width: 894px) 100vw, 894px\" \/><figcaption>Resumo da administra\u00e7\u00e3o indireta<\/figcaption><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-conclus-o-do-resumo-de-direito-administrativo-para-pf-parte-2\"><br \/>Conclus\u00e3o do resumo de direito administrativo para PF parte 2<\/h2>\n\n\n\n<p><br \/><br \/>E ent\u00e3o, esperamos que tenha aproveitado esse resumo dos principais t\u00f3picos de direito administrativo para a prova da PF e feito as anota\u00e7\u00f5es pertinentes para a prova. Mas, se ap\u00f3s a leitura desse artigo, for necess\u00e1rio aprofundar e aprender ainda mais sobre esses conte\u00fados, indica-se o curso completo.<br \/><br \/><br \/>At\u00e9 a posse!<br \/><br \/>Taciana Rummler<br \/>Instagram: @tacirummler<br \/><\/p>\n\n\n\n<p class=\"has-black-color has-text-color has-medium-font-size\"><strong><em>Assinatura Anual Ilimitada*<\/em><\/strong>&nbsp;<\/p>\n\n\n\n<p>Ent\u00e3o, p<em>repare-se com o melhor material e com quem mais aprova em Concursos P\u00fablicos em todo o pa\u00eds<\/em> e a<em>ssine agora a nossa Assinatura Anual e tenha acesso ilimitado* a todos os nossos cursos.<\/em><\/p>\n\n\n\n<p class=\"has-text-align-center has-black-color has-pale-cyan-blue-background-color has-text-color has-background\" style=\"font-size:clamp(14.642px, 0.915rem + ((1vw - 3.2px) * 0.721), 22px);px\"><strong>ASSINE AGORA<\/strong>&nbsp;\u2013&nbsp;<strong><a href=\"https:\/\/www.estrategiaconcursos.com.br\/assinaturas\" target=\"_blank\" rel=\"noreferrer noopener\">Assinatura Ilimitada<\/a><\/strong><\/p>\n\n\n\n<p class=\"has-medium-font-size\"><strong><em>Sistema de Quest\u00f5es<\/em><\/strong><\/p>\n\n\n\n<p><em>Estrat\u00e9gia Quest\u00f5es nasceu maior do que todos os concorrentes, com mais quest\u00f5es cadastradas e mais solu\u00e7\u00f5es por professores. Ent\u00e3o, confira e aproveite os descontos e b\u00f4nus imperd\u00edveis!<\/em><\/p>\n\n\n\n<p class=\"has-text-align-center has-black-color has-light-green-cyan-background-color has-text-color has-background\" style=\"font-size:clamp(14.082px, 0.88rem + ((1vw - 3.2px) * 0.678), 21px);px\"><strong>ASSINE AGORA \u2013&nbsp;<\/strong><a href=\"https:\/\/questoes.estrategiaconcursos.com.br\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Sistema de Quest\u00f5es<\/strong><\/a><\/p>\n\n\n\n<p class=\"has-medium-font-size\"><strong><em>Pois f<\/em><\/strong><em><strong>ique por dentro dos concursos em aberto<\/strong><\/em><\/p>\n\n\n\n<p class=\"has-text-align-center has-black-color has-luminous-vivid-amber-background-color has-text-color has-background\" style=\"font-size:clamp(14.642px, 0.915rem + ((1vw - 3.2px) * 0.721), 22px);px\"><strong><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-abertos\/\" target=\"_blank\" rel=\"noreferrer noopener\">CONCURSOS ABERTOS<\/a><\/strong><\/p>\n\n\n\n<p class=\"has-medium-font-size\"><em><strong>E ent\u00e3o veja tamb\u00e9m as oportunidades previstas!<\/strong><\/em><\/p>\n\n\n\n<p class=\"has-text-align-center has-black-color has-text-color has-background\" style=\"background-color:#cf7330;font-size:clamp(14.642px, 0.915rem + ((1vw - 3.2px) * 0.721), 22px);px\"><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-2021\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>CONCURSOS 2021<\/strong><\/a><\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Fala, pessoal. Ent\u00e3o, nesse artigo vamos fazer um resumo sobre os principais pontos de direito administrativo para a prova da PF. Conforme an\u00e1lise, verificamos que os temas de maiores relev\u00e2ncia s\u00e3o: Dividiremos os assuntos em dois artigos para que sejam mais bem abordados. Na parte um falamos sobre os poderes administrativos e gente p\u00fablicos. E [&hellip;]<\/p>\n","protected":false},"author":1882,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"post_tipo":"article","footnotes":""},"categories":[220015,1,164300,6741,2185,220016],"tags":[],"tax_estado":[219964,219965,219966,219967,219968,219969,219963,219970,219971,219972,219973,219974,219975,219976,219977,219978,219979,219980,219981,219982,219983,219984,219985,219986,219987,219988,219989,219990],"class_list":["post-685885","post","type-post","status-publish","format-standard","hentry","category-cfc","category-cursos-e-concursos","category-concurso-diplomacia","category-forcas-armadas-oficiais","category-carreiras-juridicas","category-cartorios","tax_estado-ac","tax_estado-al","tax_estado-am","tax_estado-ap","tax_estado-ba","tax_estado-ce","tax_estado-concursos-federais","tax_estado-df","tax_estado-es","tax_estado-go","tax_estado-ma","tax_estado-mg","tax_estado-ms","tax_estado-mt","tax_estado-pa","tax_estado-pb","tax_estado-pe","tax_estado-pi","tax_estado-pr","tax_estado-rj","tax_estado-rn","tax_estado-ro","tax_estado-rr","tax_estado-rs","tax_estado-sc","tax_estado-se","tax_estado-sp","tax_estado-to"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.2 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Resumo de direito administrativo PF Parte 2: principais t\u00f3picos<\/title>\n<meta name=\"description\" content=\"Nessa continua\u00e7\u00e3o do resumo de direito administrativo para a prova da PF, abordaremos os princ\u00edpios e a organiza\u00e7\u00e3o administrativa.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/reta-final-direito-administrativo-para-pf\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Resumo de direito administrativo para PF - Princ\u00edpios e Organiza\u00e7\u00e3o administrativa\" \/>\n<meta property=\"og:description\" content=\"Nessa continua\u00e7\u00e3o do resumo de direito administrativo para a prova da PF, abordaremos os princ\u00edpios e a organiza\u00e7\u00e3o administrativa.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/reta-final-direito-administrativo-para-pf\/\" \/>\n<meta property=\"og:site_name\" content=\"Estrat\u00e9gia Concursos\" \/>\n<meta property=\"article:published_time\" content=\"2021-03-15T19:40:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-content\/uploads\/2021\/03\/temas-e-incidencia-pf-e-prf.png\" \/>\n<meta name=\"author\" content=\"Taciana de Oliveira Rummler\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:site\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Taciana de Oliveira Rummler\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"11 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/reta-final-direito-administrativo-para-pf\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/reta-final-direito-administrativo-para-pf\/\"},\"author\":{\"name\":\"Taciana de Oliveira Rummler\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/c932827075ce3b63fed346d72ebc117f\"},\"headline\":\"Resumo de direito administrativo para PF &#8211; Princ\u00edpios e Organiza\u00e7\u00e3o administrativa\",\"datePublished\":\"2021-03-15T19:40:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/reta-final-direito-administrativo-para-pf\/\"},\"wordCount\":2267,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/reta-final-direito-administrativo-para-pf\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-content\/uploads\/2021\/03\/temas-e-incidencia-pf-e-prf.png\",\"articleSection\":[\"CFC\",\"Concursos P\u00fablicos\",\"Diplomacia (CACD)\",\"For\u00e7as Armadas (Oficiais)\",\"Jur\u00eddico\",\"Jur\u00eddico - Cart\u00f3rios\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/reta-final-direito-administrativo-para-pf\/#respond\"]}],\"copyrightYear\":\"2021\",\"copyrightHolder\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/reta-final-direito-administrativo-para-pf\/\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/reta-final-direito-administrativo-para-pf\/\",\"name\":\"Resumo de direito administrativo PF Parte 2: principais t\u00f3picos\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/reta-final-direito-administrativo-para-pf\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/reta-final-direito-administrativo-para-pf\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-content\/uploads\/2021\/03\/temas-e-incidencia-pf-e-prf.png\",\"datePublished\":\"2021-03-15T19:40:00+00:00\",\"description\":\"Nessa continua\u00e7\u00e3o do resumo de direito administrativo para a prova da PF, abordaremos os princ\u00edpios e a organiza\u00e7\u00e3o administrativa.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/reta-final-direito-administrativo-para-pf\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/reta-final-direito-administrativo-para-pf\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/reta-final-direito-administrativo-para-pf\/#primaryimage\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/03\/05112025\/temas-e-incidencia-pf-e-prf.png\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/03\/05112025\/temas-e-incidencia-pf-e-prf.png\",\"width\":455,\"height\":145,\"caption\":\"Temas e incid\u00eancia de Direito administrativo para PF\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/reta-final-direito-administrativo-para-pf\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Resumo de direito administrativo para PF &#8211; Princ\u00edpios e Organiza\u00e7\u00e3o administrativa\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"name\":\"Estrat\u00e9gia Concursos\",\"description\":\"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.\",\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\",\"name\":\"Estrat\u00e9gia Concursos\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"width\":230,\"height\":60,\"caption\":\"Estrat\u00e9gia Concursos\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/EstratConcursos\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/c932827075ce3b63fed346d72ebc117f\",\"name\":\"Taciana de Oliveira Rummler\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/7e053d5a1ee8015f21290f2e1a81c8760c702882945b8c6a5ada1196c048a0e4?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/7e053d5a1ee8015f21290f2e1a81c8760c702882945b8c6a5ada1196c048a0e4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/7e053d5a1ee8015f21290f2e1a81c8760c702882945b8c6a5ada1196c048a0e4?s=96&d=mm&r=g\",\"caption\":\"Taciana de Oliveira Rummler\"},\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/tacirummlerhotmail-com\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Resumo de direito administrativo PF Parte 2: principais t\u00f3picos","description":"Nessa continua\u00e7\u00e3o do resumo de direito administrativo para a prova da PF, abordaremos os princ\u00edpios e a organiza\u00e7\u00e3o administrativa.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.estrategiaconcursos.com.br\/blog\/reta-final-direito-administrativo-para-pf\/","og_locale":"pt_BR","og_type":"article","og_title":"Resumo de direito administrativo para PF - Princ\u00edpios e Organiza\u00e7\u00e3o administrativa","og_description":"Nessa continua\u00e7\u00e3o do resumo de direito administrativo para a prova da PF, abordaremos os princ\u00edpios e a organiza\u00e7\u00e3o administrativa.","og_url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/reta-final-direito-administrativo-para-pf\/","og_site_name":"Estrat\u00e9gia Concursos","article_published_time":"2021-03-15T19:40:00+00:00","og_image":[{"url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-content\/uploads\/2021\/03\/temas-e-incidencia-pf-e-prf.png","type":"","width":"","height":""}],"author":"Taciana de Oliveira Rummler","twitter_card":"summary_large_image","twitter_creator":"@EstratConcursos","twitter_site":"@EstratConcursos","twitter_misc":{"Escrito por":"Taciana de Oliveira Rummler","Est. tempo de leitura":"11 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/reta-final-direito-administrativo-para-pf\/#article","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/reta-final-direito-administrativo-para-pf\/"},"author":{"name":"Taciana de Oliveira Rummler","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/c932827075ce3b63fed346d72ebc117f"},"headline":"Resumo de direito administrativo para PF &#8211; Princ\u00edpios e Organiza\u00e7\u00e3o administrativa","datePublished":"2021-03-15T19:40:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/reta-final-direito-administrativo-para-pf\/"},"wordCount":2267,"commentCount":0,"publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/reta-final-direito-administrativo-para-pf\/#primaryimage"},"thumbnailUrl":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-content\/uploads\/2021\/03\/temas-e-incidencia-pf-e-prf.png","articleSection":["CFC","Concursos P\u00fablicos","Diplomacia (CACD)","For\u00e7as Armadas (Oficiais)","Jur\u00eddico","Jur\u00eddico - Cart\u00f3rios"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/reta-final-direito-administrativo-para-pf\/#respond"]}],"copyrightYear":"2021","copyrightHolder":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/reta-final-direito-administrativo-para-pf\/","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/reta-final-direito-administrativo-para-pf\/","name":"Resumo de direito administrativo PF Parte 2: principais t\u00f3picos","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/reta-final-direito-administrativo-para-pf\/#primaryimage"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/reta-final-direito-administrativo-para-pf\/#primaryimage"},"thumbnailUrl":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-content\/uploads\/2021\/03\/temas-e-incidencia-pf-e-prf.png","datePublished":"2021-03-15T19:40:00+00:00","description":"Nessa continua\u00e7\u00e3o do resumo de direito administrativo para a prova da PF, abordaremos os princ\u00edpios e a organiza\u00e7\u00e3o administrativa.","breadcrumb":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/reta-final-direito-administrativo-para-pf\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/reta-final-direito-administrativo-para-pf\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/reta-final-direito-administrativo-para-pf\/#primaryimage","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/03\/05112025\/temas-e-incidencia-pf-e-prf.png","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/03\/05112025\/temas-e-incidencia-pf-e-prf.png","width":455,"height":145,"caption":"Temas e incid\u00eancia de Direito administrativo para PF"},{"@type":"BreadcrumbList","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/reta-final-direito-administrativo-para-pf\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.estrategiaconcursos.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Resumo de direito administrativo para PF &#8211; Princ\u00edpios e Organiza\u00e7\u00e3o administrativa"}]},{"@type":"WebSite","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","name":"Estrat\u00e9gia Concursos","description":"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.","publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization","name":"Estrat\u00e9gia Concursos","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","width":230,"height":60,"caption":"Estrat\u00e9gia Concursos"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/EstratConcursos"]},{"@type":"Person","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/c932827075ce3b63fed346d72ebc117f","name":"Taciana de Oliveira Rummler","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/7e053d5a1ee8015f21290f2e1a81c8760c702882945b8c6a5ada1196c048a0e4?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/7e053d5a1ee8015f21290f2e1a81c8760c702882945b8c6a5ada1196c048a0e4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7e053d5a1ee8015f21290f2e1a81c8760c702882945b8c6a5ada1196c048a0e4?s=96&d=mm&r=g","caption":"Taciana de Oliveira Rummler"},"url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/tacirummlerhotmail-com\/"}]}},"_links":{"self":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/685885","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/users\/1882"}],"replies":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/comments?post=685885"}],"version-history":[{"count":15,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/685885\/revisions"}],"predecessor-version":[{"id":691135,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/685885\/revisions\/691135"}],"wp:attachment":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media?parent=685885"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/categories?post=685885"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tags?post=685885"},{"taxonomy":"tax_estado","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tax_estado?post=685885"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}