{"id":660393,"date":"2021-02-01T12:00:00","date_gmt":"2021-02-01T15:00:00","guid":{"rendered":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?p=660393"},"modified":"2021-01-29T16:32:26","modified_gmt":"2021-01-29T19:32:26","slug":"delegado-de-policia-como-pontuar-na-prova-de-titulos","status":"publish","type":"post","link":"https:\/\/www.estrategiaconcursos.com.br\/blog\/delegado-de-policia-como-pontuar-na-prova-de-titulos\/","title":{"rendered":"Delegado de pol\u00edcia: como pontuar na prova de t\u00edtulos?"},"content":{"rendered":"\n<p><em>Entenda quais s\u00e3o as melhores op\u00e7\u00f5es de p\u00f3s-gradua\u00e7\u00e3o para alunos que desejam seguir a carreira de delta<\/em><\/p>\n\n\n\n<p>Ser delegado de pol\u00edcia \u00e9 o grande sonho de muitos alunos formados em Direito: a paix\u00e3o pela \u00e1rea policial e a oportunidade de exercer um cargo t\u00e3o importante para a nossa sociedade s\u00e3o os fatores que norteiam os estudos desses concurseiros.&nbsp;<\/p>\n\n\n\n<p>2021 j\u00e1 mostrou que ser\u00e1 um grande ano para a carreira policial: foi lan\u00e7ado o t\u00e3o aguardado edital para a Pol\u00edcia Federal (PF), al\u00e9m de outros editais vigentes para carreiras policiais nos estados da federa\u00e7\u00e3o.&nbsp;<\/p>\n\n\n\n<p>Uma das etapas do concurso p\u00fablico da PF &#8211; assim como para outros \u00f3rg\u00e3os &#8211; \u00e9 a atribui\u00e7\u00e3o de pontos para os candidatos que apresentam t\u00edtulos como uma especializa\u00e7\u00e3o lato sensu e um mestrado. Dessa forma, no post de hoje, vamos analisar como \u00e9 poss\u00edvel pontuar nessa etapa do concurso de forma estrat\u00e9gica e otimizada.&nbsp;<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-1-as-etapas-do-concurso-para-delegado-de-pol-cia-e-a-prova-de-t-tulos\">1) As etapas do concurso para delegado de pol\u00edcia e a prova de t\u00edtulos<\/h2>\n\n\n\n<p>Veja que, ao longo do nosso artigo, utilizaremos o edital da Pol\u00edcia Federal para o cargo de Delegado como base. Contudo, voc\u00ea pode fazer esse mesmo tipo de an\u00e1lise ao verificar as informa\u00e7\u00f5es apresentadas no edital do seu concurso de prefer\u00eancia para a carreira de delta.&nbsp;<\/p>\n\n\n\n<p>No caso da Pol\u00edcia Federal, o concurso envolve as seguintes etapas:<\/p>\n\n\n\n<ol class=\"wp-block-list\"><li>Provas objetivas e discursivas (eliminat\u00f3ria e classificat\u00f3ria);<\/li><li>Exame de Aptid\u00e3o F\u00edsica (eliminat\u00f3rio);<\/li><li>Exame M\u00e9dico (eliminat\u00f3rio);<\/li><li>Prova Oral (eliminat\u00f3ria e classificat\u00f3ria);<\/li><li>Avalia\u00e7\u00e3o de T\u00edtulos (classificat\u00f3ria); e<\/li><li>Avalia\u00e7\u00e3o Psicol\u00f3gica (eliminat\u00f3ria).<\/li><\/ol>\n\n\n\n<p>Al\u00e9m das seis etapas acima descritas, o profissional aprovado tamb\u00e9m precisar\u00e1 passar por um curso de forma\u00e7\u00e3o para efetivamente exercer as atividades de delegado.&nbsp;<\/p>\n\n\n\n<p>Perceba, portanto, que a avalia\u00e7\u00e3o de t\u00edtulos \u00e9 classificat\u00f3ria: se voc\u00ea n\u00e3o apresentar t\u00edtulos, n\u00e3o ser\u00e1 eliminado do certame por esse motivo. No entanto, \u00e9 aqui que existe o &#8220;pulo do gato&#8221; nesse tipo de concurso: muitos candidatos ignoram a import\u00e2ncia de uma prova de t\u00edtulos e, dessa forma, n\u00e3o se preocupam com esse tipo de avalia\u00e7\u00e3o. Os pontos adquiridos podem ser cruciais para melhorar a classifica\u00e7\u00e3o do futuro servidor p\u00fablico, aprimorando o seu desempenho no certame.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-2-as-disciplinas-do-concurso-de-delegado-da-pol-cia-federal\">2) As disciplinas do concurso de delegado da Pol\u00edcia Federal<\/h2>\n\n\n\n<p>Uma das principais preocupa\u00e7\u00f5es de quem busca uma especializa\u00e7\u00e3o na \u00e1rea jur\u00eddica \u00e9 fazer um curso que seja compat\u00edvel com os seus objetivos profissionais. Com tantas \u00e1reas no Direito, \u00e9 indispens\u00e1vel escolher um programa de p\u00f3s-gradua\u00e7\u00e3o que contribua, de forma direta, com os conhecimentos necess\u00e1rios para o exerc\u00edcio da carreira (seja na iniciativa privada ou em um cargo como delegado de pol\u00edcia, por exemplo).&nbsp;<\/p>\n\n\n\n<p>Dessa forma, vamos considerar as disciplinas apresentadas pelo edital da Pol\u00edcia Federal:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Direito Constitucional<\/li><li>Direito Administrativo<\/li><li>Direito Penal<\/li><li>Direito Processual Penal<\/li><li>Criminologia<\/li><li>Direito Civil<\/li><li>Direito Processual Civil<\/li><li>Direito Previdenci\u00e1rio<\/li><li>Direito Financeiro e Tribut\u00e1rio<\/li><li>Direito Internacional P\u00fablico e Coopera\u00e7\u00e3o Internacional<\/li><li>Direito Empresarial<\/li><\/ul>\n\n\n\n<p>Dentre as disciplinas apresentadas, podemos destacar a relev\u00e2ncia de temas como Direito Penal, Direito Processual Penal e Criminologia, temas indispens\u00e1veis para os certames e tamb\u00e9m para o exerc\u00edcio das profiss\u00f5es nas carreiras policiais.<\/p>\n\n\n\n<p>Ao olharmos para a etapa das discursivas, vemos que as disciplinas de Direito Administrativo, Direito Constitucional, Direito Penal e Direito Processual Penal ser\u00e3o os temas abordados para que os candidatos escrevam a respeito nas quest\u00f5es abertas. Nesse contexto, vemos que o pr\u00f3prio edital da PF exige conhecimentos aprofundados nesses assuntos para que o candidato tenha um bom desempenho na prova.&nbsp;<\/p>\n\n\n\n<p>Veja, como exemplo, o conte\u00fado program\u00e1tico da disciplina de <strong>Direito Processual Penal<\/strong>:<\/p>\n\n\n\n<p><em>1 Direito processual penal. 1.1 Princ\u00edpios gerais, conceito, finalidade, caracter\u00edsticas. 1.2 Fontes. 1.3 Lei processual penal: fontes, efic\u00e1cia, interpreta\u00e7\u00e3o, analogia, imunidades. 1.4 Sistemas de processo penal. 2 Inqu\u00e9rito policial. 2.1 Hist\u00f3rico; natureza; conceito; finalidade; caracter\u00edsticas; 49 fundamento; titularidade; grau de cogni\u00e7\u00e3o; valor probat\u00f3rio; formas de instaura\u00e7\u00e3o; notitia criminis; delatio criminis; procedimentos investigativos; indiciamento; garantias do investigado; conclus\u00e3o; prazos. 2.2 Atribui\u00e7\u00f5es da pol\u00edcia federal na persecu\u00e7\u00e3o criminal: Lei n\u00ba 10.446\/2002; jurisdi\u00e7\u00e3o; compet\u00eancia; conex\u00e3o e contin\u00eancia; preven\u00e7\u00e3o; quest\u00f5es e procedimentos incidentes. 2.3 Compet\u00eancia da justi\u00e7a federal, dos tribunais regionais federais, do STJ e do STF, conflito de compet\u00eancia. 3 Processo criminal: finalidade, pressupostos e sistemas. 4 A\u00e7\u00e3o penal. 4.1 Conceito, caracter\u00edsticas, esp\u00e9cies e condi\u00e7\u00f5es. 4.2 Sujeitos do processo: juiz, Minist\u00e9rio P\u00fablico, acusado e seu defensor, assistente, curador do r\u00e9u menor, auxiliares da justi\u00e7a, assistentes, peritos e int\u00e9rpretes, serventu\u00e1rios da justi\u00e7a, impedimentos e suspei\u00e7\u00f5es. 5 Juizados especiais criminais: aplica\u00e7\u00e3o na justi\u00e7a federal. 6 Termo circunstanciado de ocorr\u00eancia; atos processuais; forma, lugar e tempo. 7 Provas. 7.1 Conceito, objeto, classifica\u00e7\u00e3o e sistemas de avalia\u00e7\u00e3o. 7.2 Princ\u00edpios gerais da prova, procedimento probat\u00f3rio. 7.3 Valora\u00e7\u00e3o. 7.4 \u00d4nus da prova. 7.5 Provas il\u00edcitas. 7.6 Meios de prova: per\u00edcias, interrogat\u00f3rio, confiss\u00e3o, testemunhas, reconhecimento de pessoas e coisas, acarea\u00e7\u00e3o, documentos, ind\u00edcios. 7.7 Busca e apreens\u00e3o: pessoal, domiciliar, requisitos, restri\u00e7\u00f5es, hor\u00e1rios. 8 Pris\u00e3o. 8.1 Conceito, esp\u00e9cies, mandado de pris\u00e3o e cumprimento. 8.2 Pris\u00e3o em flagrante. 8.3 Pris\u00e3o tempor\u00e1ria. 8.4 Pris\u00e3o preventiva. 8.5 Princ\u00edpio da necessidade, pris\u00e3o especial, liberdade provis\u00f3ria. 8.6 Fian\u00e7a. 9 Senten\u00e7a criminal. 9.1 Juiz, Minist\u00e9rio P\u00fablico, acusado e defensor, assistentes e auxiliares da justi\u00e7a. 9.2 Cita\u00e7\u00e3o, intima\u00e7\u00e3o, interdi\u00e7\u00e3o de direito. 9.3 Processos dos crimes de responsabilidade dos funcion\u00e1rios p\u00fablicos. 9.4 Senten\u00e7a: coisa julgada, habeas corpus, mandado de seguran\u00e7a em mat\u00e9ria criminal. 10 Processo criminal de crimes comuns. 10.1 Lei n\u00ba 11.343\/2006 e suas altera\u00e7\u00f5es (Tr\u00e1fico il\u00edcito e uso indevido de subst\u00e2ncias entorpecentes). 10.2 Lei n\u00ba 12.850\/2013 e suas altera\u00e7\u00f5es (Crime organizado). 10.3 Lei n\u00ba 7.492\/1986 e suas altera\u00e7\u00f5es (Crimes contra o sistema Financeiro Nacional). 10.4 Lei n\u00ba 8.137\/1990 e suas altera\u00e7\u00f5es (Crimes contra a ordem econ\u00f4mica e tribut\u00e1ria e as rela\u00e7\u00f5es de consumo). 10.5 Lei n\u00ba 9.613\/1998 e suas altera\u00e7\u00f5es (Lavagem de dinheiro). 10.6 Lei n\u00ba 8.072\/1990 e suas altera\u00e7\u00f5es (Crimes hediondos). 10.7 Lei n\u00ba 7.716\/1989 e suas altera\u00e7\u00f5es (Crimes resultantes de preconceitos de ra\u00e7a ou de cor). 10.8 Lei n\u00ba 9.455\/1997 e suas altera\u00e7\u00f5es (Crimes de tortura). 10.9 Lei n\u00ba 9.605\/1998 e suas altera\u00e7\u00f5es (Crimes contra o meio ambiente). 10.10 Crimes de responsabilidade (Decreto-Lei n\u00ba 201\/1967 e suas altera\u00e7\u00f5es, Lei n\u00ba 1.079\/1950 e suas altera\u00e7\u00f5es e Lei n\u00ba 8.176\/1991). 10.11 Lei n\u00ba 11.101\/2005 e suas altera\u00e7\u00f5es (Crimes falimentares). 10.12 Lei n\u00ba 8.666\/1993 e suas altera\u00e7\u00f5es (Crimes nas licita\u00e7\u00f5es e contratos da administra\u00e7\u00e3o p\u00fablica); Lei n\u00ba 12.037\/2009 e suas altera\u00e7\u00f5es. 11 Lei n\u00ba 9.296\/1996 (Intercepta\u00e7\u00e3o telef\u00f4nica). 12 Lei n\u00ba 13.869\/2019 (Crimes de abuso de autoridade). 13 Lei n\u00ba 10.826\/2003 e suas altera\u00e7\u00f5es (Estatuto do desarmamento). 14 Lei n\u00ba 5.553\/1968 e suas altera\u00e7\u00f5es (Apresenta\u00e7\u00e3o e uso de documento de identifica\u00e7\u00e3o pessoal). 15 Lei n\u00ba 8.078\/1990 e suas altera\u00e7\u00f5es (C\u00f3digo de Prote\u00e7\u00e3o e Defesa do Consumidor). 16 Lei n\u00ba 6.001\/1973 e suas altera\u00e7\u00f5es (Estatuto do \u00cdndio). 17 Lei n\u00ba 8.069\/1990 e suas altera\u00e7\u00f5es (Estatuto da Crian\u00e7a e do Adolescente). 18 Lei n\u00ba 4.737\/1965 e suas altera\u00e7\u00f5es (C\u00f3digo Eleitoral). 19 Lei n\u00ba 7.210\/1984 e suas altera\u00e7\u00f5es (Execu\u00e7\u00e3o Penal). 20 Lei n\u00ba 5.250\/1967 e suas altera\u00e7\u00f5es (Lei de Imprensa). 21 Lei n\u00ba 9.099\/1995 e suas altera\u00e7\u00f5es (Juizados especiais criminais). 22 Lei n\u00ba 12.830\/2013. 23 Lei n\u00ba 13.257\/2016 e suas altera\u00e7\u00f5es. 24 Lei n\u00ba 12.737\/2012 (Lei de Crimes Cibern\u00e9ticos). 25 Jurisprud\u00eancia e S\u00famulas dos Tribunais Superiores<\/em><\/p>\n\n\n\n<p>Portanto, vemos que o conte\u00fado cobrado no certame, no caso da disciplina exemplificada, \u00e9 extremamente extenso e aprofundado do ponto de vista pedag\u00f3gico. Logo, se o candidato quiser conciliar os estudos para concursos p\u00fablicos com uma p\u00f3s-gradua\u00e7\u00e3o, \u00e9 indispens\u00e1vel que esses projetos tenham um estrita rela\u00e7\u00e3o entre si, para que haja um benef\u00edcio concreto para o aprendizado e tamb\u00e9m para os resultados obtidos nas provas.&nbsp;<\/p>\n\n\n\n<p>Al\u00e9m do evidente ganho de conhecimento t\u00e9cnico proporcionado por uma p\u00f3s-gradua\u00e7\u00e3o, o Prof. Paulo Bilynskyj, da \u00e1rea de carreiras policiais do Estrat\u00e9gia Concursos, ressalta que estar nas primeiras coloca\u00e7\u00f5es em um concurso nesse tipo de carreira permite uma nomea\u00e7\u00e3o mais r\u00e1pida, assim como ser lotado em uma grande cidade.&nbsp;<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-3-as-op-es-de-p-s-gradua-o-do-estrat-gia-unyleya-para-a-rea-policial\">3) As op\u00e7\u00f5es de p\u00f3s-gradua\u00e7\u00e3o do Estrat\u00e9gia-Unyleya para a \u00e1rea policial&nbsp;<\/h2>\n\n\n\n<p>O Estrat\u00e9gia fez uma parceria com a Faculdade Unyleya, l\u00edder em educa\u00e7\u00e3o superior no nosso pa\u00eds, para oferecer programas de p\u00f3s-gradua\u00e7\u00e3o de forma remota. Voc\u00ea j\u00e1 conhece a qualidade dos cursos preparat\u00f3rios do Estrat\u00e9gia e agora tem mais uma op\u00e7\u00e3o para avan\u00e7ar nos seus estudos acad\u00eamicos e profissionais.<\/p>\n\n\n\n<p>No caso da \u00e1rea policial, n\u00f3s temos duas op\u00e7\u00f5es de p\u00f3s-gradua\u00e7\u00e3o que podem ser interessantes para os alunos que visam uma carreira na \u00e1rea. Para realizar essa indica\u00e7\u00e3o, estamos considerando os temas abordados em cada disciplina e tamb\u00e9m os assuntos de interesse dos profissionais que ser\u00e3o futuros policiais no nosso pa\u00eds. Veja:&nbsp;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-a-p-s-gradua-o-em-investiga-o-criminal-e-legisla-o-penal\">a) P\u00f3s-gradua\u00e7\u00e3o em Investiga\u00e7\u00e3o Criminal e Legisla\u00e7\u00e3o Penal<\/h3>\n\n\n\n<p>A p\u00f3s-gradua\u00e7\u00e3o pode ser conclu\u00edda em at\u00e9 9 meses e possui 360h de carga hor\u00e1ria total.<\/p>\n\n\n\n<p>Veja as disciplinas abordadas:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>A\u00e7\u00e3o Penal<\/li><li>Agentes P\u00fablicos<\/li><li>Direito Penal Constitucional<\/li><li>Direitos e Garantias Fundamentais e Direitos Humanos<\/li><li>Inqu\u00e9rito Policial<\/li><li>Legisla\u00e7\u00e3o Penal Especial<\/li><li>Organiza\u00e7\u00e3o dos Poderes e Fun\u00e7\u00f5es Essenciais \u00e0 Justi\u00e7a<\/li><li>T\u00e9cnicas de Investiga\u00e7\u00e3o Policial<\/li><\/ul>\n\n\n\n<p>Para mais informa\u00e7\u00f5es sobre a p\u00f3s-gradua\u00e7\u00e3o, <a href=\"https:\/\/posestrategia.unyleya.edu.br\/pos-graduacao-ead\/curso\/investigacao-criminal-e-legislacao-penal\">clique aqui<\/a>.&nbsp;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-b-p-s-gradua-o-em-direito-penal-e-processual-penal\">b) P\u00f3s-gradua\u00e7\u00e3o em Direito Penal e Processual Penal<\/h3>\n\n\n\n<p>Esse programa de p\u00f3s-gradua\u00e7\u00e3o faz parte dos nossos cursos direcionados para Carreiras Jur\u00eddicas e, portanto, tem uma carga hor\u00e1ria maior do que a op\u00e7\u00e3o apresentada anteriormente. Para concluir o curso, \u00e9 necess\u00e1ria a dedica\u00e7\u00e3o durante 14 meses de estudo, com 585h totais de carga hor\u00e1ria.&nbsp;<\/p>\n\n\n\n<p>Veja as disciplinas abordadas:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Crimes em Esp\u00e9cie<\/li><li>Criminologia<\/li><li>Direito Penal Econ\u00f4mico e Crimes contra a Administra\u00e7\u00e3o P\u00fablica<\/li><li>Inqu\u00e9rito Penal e Investiga\u00e7\u00f5es<\/li><li>Legisla\u00e7\u00e3o Penal Especial<\/li><li>Princ\u00edpios Processuais e A\u00e7\u00f5es Penais<\/li><li>Pris\u00f5es, Liberdade, Nulidades e Senten\u00e7a<\/li><li>Sujeitos da Rela\u00e7\u00e3o Processual e Atos Processuais<\/li><li>Teoria da Pena<\/li><li>Teoria do Delito<\/li><li>Teoria Geral das Provas e Provas em Esp\u00e9cie<\/li><li>Teoria Geral do Direito Penal<\/li><li>Teoria Geral dos Recursos e Recursos em Esp\u00e9cie<\/li><\/ul>\n\n\n\n<p>Para mais informa\u00e7\u00f5es sobre a p\u00f3s-gradua\u00e7\u00e3o, <a href=\"https:\/\/posestrategia.unyleya.edu.br\/pos-graduacao-ead\/curso\/direito-penal-e-processual-penal\">clique aqui<\/a>.&nbsp;<\/p>\n\n\n\n<p>Todos os cursos do Estrat\u00e9gia-Unyleya s\u00e3o reconhecidos pelo MEC e, portanto, podem ser utilizados para a obten\u00e7\u00e3o de pontos em provas de t\u00edtulos em concursos p\u00fablicos.&nbsp;<\/p>\n\n\n\n<p>Deixo aqui tamb\u00e9m um convite para que voc\u00ea nos acompanhe no <a href=\"https:\/\/instagram.com\/estrategiaposgraduacao\">Instagram da p\u00f3s-gradua\u00e7\u00e3o<\/a>! Estamos produzindo conte\u00fados incr\u00edveis para te auxiliar na sua jornada de estudos e no seu aprimoramento profissional!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Entenda quais s\u00e3o as melhores op\u00e7\u00f5es de p\u00f3s-gradua\u00e7\u00e3o para alunos que desejam seguir a carreira de delta Ser delegado de pol\u00edcia \u00e9 o grande sonho de muitos alunos formados em Direito: a paix\u00e3o pela \u00e1rea policial e a oportunidade de exercer um cargo t\u00e3o importante para a nossa sociedade s\u00e3o os fatores que norteiam os [&hellip;]<\/p>\n","protected":false},"author":1432,"featured_media":660406,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"post_tipo":"article","footnotes":""},"categories":[2185,1988],"tags":[2239,754,1582,1570,56299],"tax_estado":[219964,219965,219966,219967,219968,219969,219963,219970,219971,219972,219973,219974,219975,219976,219977,219978,219979,219980,219981,219982,219983,219984,219985,219986,219987,219988,219989,219990],"class_list":["post-660393","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-carreiras-juridicas","category-policia","tag-carreiras-juridicas","tag-delegado","tag-delegado-de-policia","tag-delta","tag-pos-graduacao","tax_estado-ac","tax_estado-al","tax_estado-am","tax_estado-ap","tax_estado-ba","tax_estado-ce","tax_estado-concursos-federais","tax_estado-df","tax_estado-es","tax_estado-go","tax_estado-ma","tax_estado-mg","tax_estado-ms","tax_estado-mt","tax_estado-pa","tax_estado-pb","tax_estado-pe","tax_estado-pi","tax_estado-pr","tax_estado-rj","tax_estado-rn","tax_estado-ro","tax_estado-rr","tax_estado-rs","tax_estado-sc","tax_estado-se","tax_estado-sp","tax_estado-to"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.2 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Delegado de pol\u00edcia: como pontuar na prova de t\u00edtulos?<\/title>\n<meta name=\"description\" content=\"Veja como voc\u00ea pode pontuar nas provas de t\u00edtulos para o cargo de Delegado de Pol\u00edcia, de acordo com as orienta\u00e7\u00f5es da equipe do Estrat\u00e9gia..\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/delegado-de-policia-como-pontuar-na-prova-de-titulos\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Delegado de pol\u00edcia: como pontuar na prova de t\u00edtulos?\" \/>\n<meta property=\"og:description\" content=\"Veja como voc\u00ea pode pontuar nas provas de t\u00edtulos para o cargo de Delegado de Pol\u00edcia, de acordo com as orienta\u00e7\u00f5es da equipe do Estrat\u00e9gia..\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/delegado-de-policia-como-pontuar-na-prova-de-titulos\/\" \/>\n<meta property=\"og:site_name\" content=\"Estrat\u00e9gia Concursos\" \/>\n<meta property=\"article:published_time\" content=\"2021-02-01T15:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/01\/29163116\/brasao_policia_federal_auditorio_rn.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1632\" \/>\n\t<meta property=\"og:image:height\" content=\"1224\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"J\u00falia Branco\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:site\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"J\u00falia Branco\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"9 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/delegado-de-policia-como-pontuar-na-prova-de-titulos\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/delegado-de-policia-como-pontuar-na-prova-de-titulos\/\"},\"author\":{\"name\":\"J\u00falia Branco\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/8a4a2ce92e69596f6fc586bac2e00aa6\"},\"headline\":\"Delegado de pol\u00edcia: como pontuar na prova de t\u00edtulos?\",\"datePublished\":\"2021-02-01T15:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/delegado-de-policia-como-pontuar-na-prova-de-titulos\/\"},\"wordCount\":1855,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/delegado-de-policia-como-pontuar-na-prova-de-titulos\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/01\/29163116\/brasao_policia_federal_auditorio_rn.jpg\",\"keywords\":[\"carreiras jur\u00eddicas\",\"Delegado\",\"Delegado de Pol\u00edcia\",\"delta\",\"p\u00f3s-gradua\u00e7\u00e3o\"],\"articleSection\":[\"Jur\u00eddico\",\"Policial (Agente, Escriv\u00e3o e Investigador)\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/delegado-de-policia-como-pontuar-na-prova-de-titulos\/#respond\"]}],\"copyrightYear\":\"2021\",\"copyrightHolder\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/delegado-de-policia-como-pontuar-na-prova-de-titulos\/\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/delegado-de-policia-como-pontuar-na-prova-de-titulos\/\",\"name\":\"Delegado de pol\u00edcia: como pontuar na prova de t\u00edtulos?\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/delegado-de-policia-como-pontuar-na-prova-de-titulos\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/delegado-de-policia-como-pontuar-na-prova-de-titulos\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/01\/29163116\/brasao_policia_federal_auditorio_rn.jpg\",\"datePublished\":\"2021-02-01T15:00:00+00:00\",\"description\":\"Veja como voc\u00ea pode pontuar nas provas de t\u00edtulos para o cargo de Delegado de Pol\u00edcia, de acordo com as orienta\u00e7\u00f5es da equipe do Estrat\u00e9gia..\",\"breadcrumb\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/delegado-de-policia-como-pontuar-na-prova-de-titulos\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/delegado-de-policia-como-pontuar-na-prova-de-titulos\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/delegado-de-policia-como-pontuar-na-prova-de-titulos\/#primaryimage\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/01\/29163116\/brasao_policia_federal_auditorio_rn.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/01\/29163116\/brasao_policia_federal_auditorio_rn.jpg\",\"width\":1632,\"height\":1224,\"caption\":\"Carreiras da Pol\u00edcia Federal\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/delegado-de-policia-como-pontuar-na-prova-de-titulos\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Delegado de pol\u00edcia: como pontuar na prova de t\u00edtulos?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"name\":\"Estrat\u00e9gia Concursos\",\"description\":\"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.\",\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\",\"name\":\"Estrat\u00e9gia Concursos\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"width\":230,\"height\":60,\"caption\":\"Estrat\u00e9gia Concursos\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/EstratConcursos\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/8a4a2ce92e69596f6fc586bac2e00aa6\",\"name\":\"J\u00falia Branco\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/0f766fa82cc670dc5dc1bfb2b089001368538ed907cbd3f55bb04c1f70f134b5?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/0f766fa82cc670dc5dc1bfb2b089001368538ed907cbd3f55bb04c1f70f134b5?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/0f766fa82cc670dc5dc1bfb2b089001368538ed907cbd3f55bb04c1f70f134b5?s=96&d=mm&r=g\",\"caption\":\"J\u00falia Branco\"},\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/juliakbrancogmail-com\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Delegado de pol\u00edcia: como pontuar na prova de t\u00edtulos?","description":"Veja como voc\u00ea pode pontuar nas provas de t\u00edtulos para o cargo de Delegado de Pol\u00edcia, de acordo com as orienta\u00e7\u00f5es da equipe do Estrat\u00e9gia..","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.estrategiaconcursos.com.br\/blog\/delegado-de-policia-como-pontuar-na-prova-de-titulos\/","og_locale":"pt_BR","og_type":"article","og_title":"Delegado de pol\u00edcia: como pontuar na prova de t\u00edtulos?","og_description":"Veja como voc\u00ea pode pontuar nas provas de t\u00edtulos para o cargo de Delegado de Pol\u00edcia, de acordo com as orienta\u00e7\u00f5es da equipe do Estrat\u00e9gia..","og_url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/delegado-de-policia-como-pontuar-na-prova-de-titulos\/","og_site_name":"Estrat\u00e9gia Concursos","article_published_time":"2021-02-01T15:00:00+00:00","og_image":[{"width":1632,"height":1224,"url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/01\/29163116\/brasao_policia_federal_auditorio_rn.jpg","type":"image\/jpeg"}],"author":"J\u00falia Branco","twitter_card":"summary_large_image","twitter_creator":"@EstratConcursos","twitter_site":"@EstratConcursos","twitter_misc":{"Escrito por":"J\u00falia Branco","Est. tempo de leitura":"9 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/delegado-de-policia-como-pontuar-na-prova-de-titulos\/#article","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/delegado-de-policia-como-pontuar-na-prova-de-titulos\/"},"author":{"name":"J\u00falia Branco","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/8a4a2ce92e69596f6fc586bac2e00aa6"},"headline":"Delegado de pol\u00edcia: como pontuar na prova de t\u00edtulos?","datePublished":"2021-02-01T15:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/delegado-de-policia-como-pontuar-na-prova-de-titulos\/"},"wordCount":1855,"commentCount":0,"publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/delegado-de-policia-como-pontuar-na-prova-de-titulos\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/01\/29163116\/brasao_policia_federal_auditorio_rn.jpg","keywords":["carreiras jur\u00eddicas","Delegado","Delegado de Pol\u00edcia","delta","p\u00f3s-gradua\u00e7\u00e3o"],"articleSection":["Jur\u00eddico","Policial (Agente, Escriv\u00e3o e Investigador)"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/delegado-de-policia-como-pontuar-na-prova-de-titulos\/#respond"]}],"copyrightYear":"2021","copyrightHolder":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/delegado-de-policia-como-pontuar-na-prova-de-titulos\/","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/delegado-de-policia-como-pontuar-na-prova-de-titulos\/","name":"Delegado de pol\u00edcia: como pontuar na prova de t\u00edtulos?","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/delegado-de-policia-como-pontuar-na-prova-de-titulos\/#primaryimage"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/delegado-de-policia-como-pontuar-na-prova-de-titulos\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/01\/29163116\/brasao_policia_federal_auditorio_rn.jpg","datePublished":"2021-02-01T15:00:00+00:00","description":"Veja como voc\u00ea pode pontuar nas provas de t\u00edtulos para o cargo de Delegado de Pol\u00edcia, de acordo com as orienta\u00e7\u00f5es da equipe do Estrat\u00e9gia..","breadcrumb":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/delegado-de-policia-como-pontuar-na-prova-de-titulos\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/delegado-de-policia-como-pontuar-na-prova-de-titulos\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/delegado-de-policia-como-pontuar-na-prova-de-titulos\/#primaryimage","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/01\/29163116\/brasao_policia_federal_auditorio_rn.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/01\/29163116\/brasao_policia_federal_auditorio_rn.jpg","width":1632,"height":1224,"caption":"Carreiras da Pol\u00edcia Federal"},{"@type":"BreadcrumbList","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/delegado-de-policia-como-pontuar-na-prova-de-titulos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.estrategiaconcursos.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Delegado de pol\u00edcia: como pontuar na prova de t\u00edtulos?"}]},{"@type":"WebSite","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","name":"Estrat\u00e9gia Concursos","description":"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.","publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization","name":"Estrat\u00e9gia Concursos","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","width":230,"height":60,"caption":"Estrat\u00e9gia Concursos"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/EstratConcursos"]},{"@type":"Person","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/8a4a2ce92e69596f6fc586bac2e00aa6","name":"J\u00falia Branco","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/0f766fa82cc670dc5dc1bfb2b089001368538ed907cbd3f55bb04c1f70f134b5?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/0f766fa82cc670dc5dc1bfb2b089001368538ed907cbd3f55bb04c1f70f134b5?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0f766fa82cc670dc5dc1bfb2b089001368538ed907cbd3f55bb04c1f70f134b5?s=96&d=mm&r=g","caption":"J\u00falia Branco"},"url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/juliakbrancogmail-com\/"}]}},"_links":{"self":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/660393","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/users\/1432"}],"replies":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/comments?post=660393"}],"version-history":[{"count":1,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/660393\/revisions"}],"predecessor-version":[{"id":660409,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/660393\/revisions\/660409"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media\/660406"}],"wp:attachment":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media?parent=660393"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/categories?post=660393"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tags?post=660393"},{"taxonomy":"tax_estado","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tax_estado?post=660393"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}