{"id":658530,"date":"2021-02-04T11:20:00","date_gmt":"2021-02-04T14:20:00","guid":{"rendered":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?p=658530"},"modified":"2021-02-10T15:16:28","modified_gmt":"2021-02-10T18:16:28","slug":"consorcios-publicos-para-concurso-pf","status":"publish","type":"post","link":"https:\/\/www.estrategiaconcursos.com.br\/blog\/consorcios-publicos-para-concurso-pf\/","title":{"rendered":"Resumo da Lei de Cons\u00f3rcios P\u00fablicos para concurso PF"},"content":{"rendered":"\n<p class=\"has-medium-font-size\">Veja as principais disposi\u00e7\u00f5es da Lei 11.107 sobre cons\u00f3rcios p\u00fablicos para <a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-policia-federal\/\" target=\"_blank\" rel=\"noreferrer noopener\">concurso Pol\u00edcia Federal<\/a> e n\u00e3o erre nenhuma quest\u00e3o sobre o tema<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-medium\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"158\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/01\/27111727\/download-1-300x158.png\" alt=\"Cons\u00f3rcios P\u00fablicos para concurso PF\" class=\"wp-image-658531\" srcset=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/01\/27111727\/download-1-300x158.png 300w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/01\/27111727\/download-1.png 310w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><figcaption>Cons\u00f3rcios P\u00fablicos para concurso PF<\/figcaption><\/figure><\/div>\n\n\n\n<p>Ol\u00e1, Estrategista. Tudo joia?<\/p>\n\n\n\n<p>Um dos assuntos cobrados em direito administrativo que causam grandes \u00edndices de erros nos candidatos \u00e9 o tema cons\u00f3rcios p\u00fablicos.<\/p>\n\n\n\n<p>Em virtude disso, dissecaremos nesse artigo tudo que voc\u00ea precisa saber sobre cons\u00f3rcios p\u00fablicos para o concurso PF. Vamos l\u00e1?<\/p>\n\n\n\n<p>Para quem n\u00e3o me conhece, me chamo Leandro, sou Auditor-Fiscal da SEFAZ-SC, aprovado no \u00faltimo concurso na 24\u00ba posi\u00e7\u00e3o. Para quem quiser trocar uma ideia ou tirar uma d\u00favida, sinta-se \u00e0 vontade para me chamar nas redes sociais (<strong>Instagram: <\/strong><a href=\"https:\/\/www.instagram.com\/leandro.rms12\/\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/www.instagram.com\/leandro.rms12\/<\/a>).<\/p>\n\n\n\n<p>Em primeiro lugar, o que \u00e9 cons\u00f3rcio p\u00fablico? Nada mais \u00e9 do que uma pessoa jur\u00eddica <strong><u>criada por lei<\/u><\/strong> com a finalidade de executar a <strong><u>gest\u00e3o associada de servi\u00e7os p\u00fablicos<\/u><\/strong>.<\/p>\n\n\n\n<p>Em outras palavras, quando um servi\u00e7o p\u00fablico \u00e9 de interesse de mais de um ente federado, estes poder\u00e3o se associar para cria\u00e7\u00e3o de um cons\u00f3rcio e assim realizarem uma gest\u00e3o centralizada destes servi\u00e7os.<\/p>\n\n\n\n<p>Sendo assim, o cons\u00f3rcio p\u00fablico poder\u00e1 ser institu\u00eddo como <strong><u>associa\u00e7\u00e3o p\u00fablica<\/u><\/strong> ou <strong><u>pessoa jur\u00eddica de direito privado<\/u><\/strong>.<\/p>\n\n\n\n<p><strong>Adendo:<\/strong> A Uni\u00e3o somente participar\u00e1 de cons\u00f3rcios p\u00fablicos em que tamb\u00e9m fa\u00e7am parte todos os Estados em cujos territ\u00f3rios estejam situados os Munic\u00edpios consorciados.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-resumo-da-lei-de-cons-rcios-p-blicos-para-concurso-pf\">Resumo da Lei de Cons\u00f3rcios P\u00fablicos para concurso PF<\/h2>\n\n\n\n<p>Disp\u00f5e a Lei de Cons\u00f3rcios P\u00fablicos que os objetivos dos cons\u00f3rcios p\u00fablicos ser\u00e3o determinados pelos entes da Federa\u00e7\u00e3o que se consorciarem.<\/p>\n\n\n\n<p>Al\u00e9m disso, para o cumprimento de seus objetivos, o cons\u00f3rcio p\u00fablico poder\u00e1:<\/p>\n\n\n\n<ol class=\"wp-block-list\" type=\"1\"><li>firmar conv\u00eanios, contratos, acordos de qualquer natureza, <strong><u>receber aux\u00edlios<\/u><\/strong>, contribui\u00e7\u00f5es e subven\u00e7\u00f5es sociais ou econ\u00f4micas de outras entidades e \u00f3rg\u00e3os do governo;<\/li><li>se o cons\u00f3rcio for de <strong><u>direito p\u00fablico<\/u><\/strong>, promover <strong><u>desapropria\u00e7\u00f5es<\/u><\/strong> e <strong><u>instituir servid\u00f5es<\/u><\/strong> nos termos de declara\u00e7\u00e3o de utilidade ou necessidade p\u00fablica, ou interesse social, realizada pelo Poder P\u00fablico; e<\/li><li>ser contratado pela administra\u00e7\u00e3o direta ou indireta dos entes da Federa\u00e7\u00e3o consorciados, <strong><u>dispensada a licita\u00e7\u00e3o<\/u><\/strong>.<\/li><\/ol>\n\n\n\n<p>Estrategista, n\u00e3o deixe de memorizar os 3 itens acima. S\u00e3o bastante cobrados em provas.<\/p>\n\n\n\n<p>Uma outra informa\u00e7\u00e3o imprescind\u00edvel a se saber \u00e9 que os cons\u00f3rcios p\u00fablicos poder\u00e3o emitir documentos de cobran\u00e7a e exercer atividades de <strong><u>ARRECADA\u00c7\u00c3O DE TARIFAS<\/u><\/strong> e outros pre\u00e7os p\u00fablicos pela presta\u00e7\u00e3o de servi\u00e7os ou pelo uso ou outorga de uso de bens p\u00fablicos por eles administrados ou, mediante autoriza\u00e7\u00e3o espec\u00edfica, pelo ente da Federa\u00e7\u00e3o consorciado.<\/p>\n\n\n\n<p><strong>Pegadinha:<\/strong> tarifa distingue-se de taxa. Esta \u00e9 tributo, aquela n\u00e3o. Portanto, os cons\u00f3rcios <strong><u>n\u00e3o<\/u><\/strong> podem exercer atividades de arrecada\u00e7\u00e3o tribut\u00e1ria.<\/p>\n\n\n\n<p>Al\u00e9m do mais, os cons\u00f3rcios n\u00e3o precisam exercer as atividades de presta\u00e7\u00e3o dos servi\u00e7os comuns diretamente. Dessa forma, os cons\u00f3rcios poder\u00e3o outorgar concess\u00e3o, permiss\u00e3o ou autoriza\u00e7\u00e3o de obras ou servi\u00e7os p\u00fablicos mediante <strong><u>autoriza\u00e7\u00e3o prevista no contrato<\/u><\/strong> de cons\u00f3rcio p\u00fablico.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-protocolo-de-inten-es\">Protocolo de Inten\u00e7\u00f5es<\/h2>\n\n\n\n<p>N\u00e3o podemos falar sobre cons\u00f3rcios p\u00fablicos sem falar do termo mais importante desse assunto: <strong><u>o protocolo de inten\u00e7\u00f5es<\/u><\/strong>.<\/p>\n\n\n\n<p>Protocolo de inten\u00e7\u00f5es nada mais \u00e9 que o instrumento pelo qual os participantes de cons\u00f3rcios p\u00fablicos fixam as regras a serem observadas.<\/p>\n\n\n\n<p>Nesse sentido, memorizem: o cons\u00f3rcio p\u00fablico ser\u00e1 constitu\u00eddo por <strong><u>CONTRATO<\/u><\/strong> cuja celebra\u00e7\u00e3o depender\u00e1 da <strong><u>pr\u00e9via subscri\u00e7\u00e3o de protocolo de inten\u00e7\u00f5es<\/u><\/strong>.<\/p>\n\n\n\n<p>Outrossim, o protocolo de inten\u00e7\u00f5es dever\u00e1 ser publicado na imprensa oficial.<\/p>\n\n\n\n<p>Al\u00e9m disso, vejam as principais cl\u00e1usulas obrigat\u00f3rias ao protocolo de inten\u00e7\u00f5es:<\/p>\n\n\n\n<ol class=\"wp-block-list\" type=\"a\"><li>denomina\u00e7\u00e3o, a finalidade, o <strong><u>prazo de dura\u00e7\u00e3o<\/u><\/strong> e a <strong><u>sede do cons\u00f3rcio<\/u><\/strong>;<\/li><li>identifica\u00e7\u00e3o dos entes da Federa\u00e7\u00e3o consorciados;<\/li><li>previs\u00e3o de que o cons\u00f3rcio p\u00fablico \u00e9 associa\u00e7\u00e3o p\u00fablica ou pessoa jur\u00eddica de direito privado sem fins econ\u00f4micos;<\/li><li>crit\u00e9rios para, em assuntos de interesse comum, <strong><u>autorizar o cons\u00f3rcio p\u00fablico a representar os entes da Federa\u00e7\u00e3o<\/u><\/strong> consorciados perante outras esferas de governo;<\/li><li>previs\u00e3o de que a assembleia geral \u00e9 a <strong><u>INST\u00c2NCIA M\u00c1XIMA<\/u><\/strong> do cons\u00f3rcio p\u00fablico e o n\u00famero de votos para as suas delibera\u00e7\u00f5es;<\/li><li>forma de elei\u00e7\u00e3o e a dura\u00e7\u00e3o do mandato do representante legal do cons\u00f3rcio p\u00fablico que, <strong><u>obrigatoriamente<\/u><\/strong>, dever\u00e1 ser <strong><u>Chefe do Poder Executivo<\/u><\/strong> de ente da Federa\u00e7\u00e3o consorciado;<\/li><li>condi\u00e7\u00f5es para que o cons\u00f3rcio p\u00fablico celebre <strong><u>contrato de gest\u00e3o<\/u><\/strong> ou <strong><u>termo de parceria;<\/u><\/strong><\/li><li>o direito de <strong><u>qualquer dos contratantes<\/u><\/strong>, quando <strong><u>adimplente<\/u><\/strong> com suas obriga\u00e7\u00f5es, de <strong><u>exigir o pleno cumprimento<\/u><\/strong> das cl\u00e1usulas do contrato de cons\u00f3rcio p\u00fablico.<\/li><\/ol>\n\n\n\n<p>O protocolo de inten\u00e7\u00f5es deve definir o n\u00famero de votos que cada ente da Federa\u00e7\u00e3o consorciado possui na assembleia geral, sendo assegurado 1 voto a cada ente consorciado.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-rea-de-atua-o-do-cons-rcio\">\u00c1rea de Atua\u00e7\u00e3o do Cons\u00f3rcio<\/h3>\n\n\n\n<p>Considera-se como \u00e1rea de atua\u00e7\u00e3o do cons\u00f3rcio p\u00fablico, <strong><u>independentemente de figurar a Uni\u00e3o como consorciada<\/u><\/strong>, a que corresponde \u00e0 soma dos territ\u00f3rios dos:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Munic\u00edpios, quando o cons\u00f3rcio p\u00fablico for constitu\u00eddo somente por Munic\u00edpios ou por um Estado e Munic\u00edpios com territ\u00f3rios nele contidos;<\/li><li>Estados ou dos Estados e do Distrito Federal, quando o cons\u00f3rcio p\u00fablico for, respectivamente, constitu\u00eddo por mais de 1 Estado ou por 1 ou mais Estados e o Distrito Federal;<\/li><li>Munic\u00edpios e do Distrito Federal, quando o cons\u00f3rcio for constitu\u00eddo pelo Distrito Federal e os Munic\u00edpios.<\/li><\/ul>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-informa-es-adicionais\">Informa\u00e7\u00f5es adicionais<\/h2>\n\n\n\n<p>\u00c9 <strong><u>nula<\/u><\/strong> a cl\u00e1usula do contrato de cons\u00f3rcio que preveja determinadas <strong><u>contribui\u00e7\u00f5es financeiras ou econ\u00f4micas<\/u><\/strong> de ente da Federa\u00e7\u00e3o ao cons\u00f3rcio p\u00fablico, salvo a <strong><u>doa\u00e7\u00e3o<\/u><\/strong>, destina\u00e7\u00e3o ou <strong><u>cess\u00e3o do uso<\/u><\/strong> de bens m\u00f3veis ou im\u00f3veis e as <strong><u>transfer\u00eancias<\/u><\/strong> ou <strong><u>cess\u00f5es de direitos<\/u><\/strong> operadas por for\u00e7a de gest\u00e3o associada de servi\u00e7os p\u00fablicos.<\/p>\n\n\n\n<p>Ademais, os entes da Federa\u00e7\u00e3o consorciados, ou os com eles conveniados, poder\u00e3o <strong><u>ceder servidores<\/u><\/strong>, na forma e condi\u00e7\u00f5es da legisla\u00e7\u00e3o de cada um.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-contrato-do-cons-rcio-p-blico\">Contrato do Cons\u00f3rcio P\u00fablico<\/h2>\n\n\n\n<p>Como vimos, o cons\u00f3rcio ser\u00e1 formalizado por meio de um <strong>CONTRATO ADMINISTRATIVO<\/strong>. Este contrato, por sua vez, ser\u00e1 celebrado com a ratifica\u00e7\u00e3o, <strong><u>mediante lei<\/u><\/strong>, do protocolo de inten\u00e7\u00f5es.<\/p>\n\n\n\n<p>Em outras palavras, o cons\u00f3rcio p\u00fablico exige: protocolo de inten\u00e7\u00f5es, contrato administrativo e lei espec\u00edfica.<\/p>\n\n\n\n<p>Uma informa\u00e7\u00e3o interessante sobre o contrato, \u00e9 que ele n\u00e3o necessariamente ser\u00e1 realizado por todos os entes que assinaram o protocolo de inten\u00e7\u00f5es, sendo poss\u00edvel ser assinado por apenas uma parcela destes.<\/p>\n\n\n\n<p>Al\u00e9m disso, a ratifica\u00e7\u00e3o por meio de lei realizada ap\u00f3s 2 anos da subscri\u00e7\u00e3o do protocolo de inten\u00e7\u00f5es depender\u00e1 de homologa\u00e7\u00e3o da assembleia geral do cons\u00f3rcio p\u00fablico.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-personalidade-jur-dica-do-cons-rcio\">Personalidade Jur\u00eddica do Cons\u00f3rcio<\/h2>\n\n\n\n<p>Disp\u00f5e a lei que o cons\u00f3rcio p\u00fablico adquirir\u00e1 personalidade jur\u00eddica:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>De direito p\u00fablico, no caso de constituir <strong><u>associa\u00e7\u00e3o p\u00fablica<\/u><\/strong>, mediante a vig\u00eancia das leis de ratifica\u00e7\u00e3o do protocolo de inten\u00e7\u00f5es;<\/li><li>de direito privado, mediante o atendimento dos requisitos da legisla\u00e7\u00e3o civil.<\/li><\/ul>\n\n\n\n<p>No primeiro caso, isto \u00e9, se o cons\u00f3rcio tiver personalidade jur\u00eddica de direito p\u00fablico, o mesmo integrar\u00e1 a <strong>Administra\u00e7\u00e3o Indireta dos entes consorciados.<\/strong><\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-contrato-de-rateio\">Contrato de Rateio<\/h2>\n\n\n\n<p>O primeiro termo e mais importante que falamos sobre o tema de cons\u00f3rcios p\u00fablicos foi o Protocolo de Inten\u00e7\u00f5es. Contudo, tamb\u00e9m n\u00e3o podemos nos esquecer de outro, que \u00e9 o Contrato de Rateio.<\/p>\n\n\n\n<p>Como vimos, os entes n\u00e3o poder\u00e3o promover contribui\u00e7\u00f5es financeiras ou econ\u00f4micas ao cons\u00f3rcio p\u00fablico. Isso n\u00e3o significa que os entes n\u00e3o poder\u00e3o destinar recursos.<\/p>\n\n\n\n<p>Eles podem, mas por meio do <strong>contrato de rateio<\/strong>. Em outras palavras, os entes consorciados somente entregar\u00e3o recursos ao cons\u00f3rcio p\u00fablico mediante contrato de rateio.<\/p>\n\n\n\n<p>O contrato de rateio ser\u00e1 formalizado em cada exerc\u00edcio financeiro, e seu prazo de vig\u00eancia n\u00e3o ser\u00e1 superior ao das dota\u00e7\u00f5es que o suportam (1 ano), com exce\u00e7\u00e3o dos contratos que tenham por objeto exclusivamente projetos consistentes em programas e a\u00e7\u00f5es contemplados em plano plurianual.<\/p>\n\n\n\n<p><strong>Adendo:<\/strong> \u00c9 vedada a aplica\u00e7\u00e3o dos recursos entregues por meio de contrato de rateio para o atendimento de <strong><u>despesas gen\u00e9ricas<\/u><\/strong>, inclusive transfer\u00eancias ou <strong><u>opera\u00e7\u00f5es de cr\u00e9dito<\/u><\/strong>.<\/p>\n\n\n\n<p>Al\u00e9m do mais, poder\u00e1 ser exclu\u00eddo do cons\u00f3rcio p\u00fablico, <strong><u>ap\u00f3s pr\u00e9via suspens\u00e3o<\/u><\/strong>, o ente consorciado que n\u00e3o consignar, em sua lei or\u00e7ament\u00e1ria ou em cr\u00e9ditos adicionais, as dota\u00e7\u00f5es suficientes para suportar as despesas assumidas por meio de contrato de rateio.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-fiscaliza-o-dos-cons-rcios\">Fiscaliza\u00e7\u00e3o dos cons\u00f3rcios<\/h2>\n\n\n\n<p>Segundo a Lei de Cons\u00f3rcios P\u00fablicos, a execu\u00e7\u00e3o das receitas e despesas do cons\u00f3rcio p\u00fablico (seja de direito p\u00fablico ou privado) dever\u00e1 obedecer \u00e0s normas de <strong><u>direito financeiro aplic\u00e1veis \u00e0s entidades p\u00fablicas<\/u><\/strong>.<\/p>\n\n\n\n<p>Outrossim, o cons\u00f3rcio p\u00fablico est\u00e1 sujeito \u00e0 fiscaliza\u00e7\u00e3o cont\u00e1bil, operacional e patrimonial pelo Tribunal de Contas competente para apreciar as contas do Chefe do Poder Executivo <strong><u>representante legal do cons\u00f3rcio<\/u><\/strong>, inclusive quanto \u00e0 legalidade, legitimidade e economicidade das despesas, atos, contratos e ren\u00fancia de receitas, sem preju\u00edzo do controle externo a ser exercido em raz\u00e3o de cada um dos contratos de rateio.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-sa-da-de-um-ente-do-cons-rcio\">Sa\u00edda de um ente do cons\u00f3rcio<\/h2>\n\n\n\n<p>Em primeiro lugar, a retirada de um ente da Federa\u00e7\u00e3o do cons\u00f3rcio p\u00fablico depender\u00e1 de ato formal de seu representante na assembleia geral.<\/p>\n\n\n\n<p>Em segundo, os bens destinados ao cons\u00f3rcio p\u00fablico pelo consorciado que se retira somente ser\u00e3o revertidos ou retrocedidos no caso de expressa previs\u00e3o no contrato ou no instrumento de transfer\u00eancia ou de aliena\u00e7\u00e3o. Caso contr\u00e1rio, estes bens ficar\u00e3o como de propriedade do cons\u00f3rcio.<\/p>\n\n\n\n<p><strong>Informa\u00e7\u00e3o Importante<\/strong>: At\u00e9 que haja decis\u00e3o que indique os respons\u00e1veis por cada obriga\u00e7\u00e3o, os entes consorciados responder\u00e3o <strong><u>SOLIDARIAMENTE<\/u><\/strong> pelas obriga\u00e7\u00f5es remanescentes, garantindo o <strong><u>direito de regresso<\/u><\/strong> em face dos entes beneficiados ou dos que deram causa \u00e0 obriga\u00e7\u00e3o.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-contrato-de-programa\">Contrato de Programa<\/h2>\n\n\n\n<p>N\u00e3o poder\u00edamos finalizar este artigo sem falar do contrato de programa. S\u00e3o muitos termos, n\u00e3o \u00e9 mesmo?<\/p>\n\n\n\n<p>Protocolo de Inten\u00e7\u00f5es, Contrato de rateio e agora Contrato de Programa.<\/p>\n\n\n\n<p>Em breves palavras, contrato de programa \u00e9 um documento que constitui as obriga\u00e7\u00f5es de ente para com outro ente da Federa\u00e7\u00e3o ou para com cons\u00f3rcio p\u00fablico.<\/p>\n\n\n\n<p><strong>Adendo: <\/strong>\u00c9 nula a cl\u00e1usula de contrato de programa que atribuir ao contratado o exerc\u00edcio dos poderes de planejamento, regula\u00e7\u00e3o e fiscaliza\u00e7\u00e3o dos servi\u00e7os por ele pr\u00f3prio prestados.<\/p>\n\n\n\n<p>Al\u00e9m disso, o contrato de programa <strong><u>continuar\u00e1 vigente<\/u><\/strong> mesmo quando <strong><u>extinto o cons\u00f3rcio p\u00fablico<\/u><\/strong> ou o conv\u00eanio de coopera\u00e7\u00e3o que autorizou a gest\u00e3o associada de servi\u00e7os p\u00fablicos.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-finalizando\">Finalizando<\/h2>\n\n\n\n<p>Ufa! Bastante informa\u00e7\u00e3o n\u00e3o \u00e9 mesmo?<\/p>\n\n\n\n<p>\u00c9 justamente por isso que esse assunto causa tantos erros para os concurseiros. Se quiser ser aprovado, sugiro que imprima este artigo sobre cons\u00f3rcios p\u00fablicos para concurso PF e estude-o quantas vezes forem necess\u00e1rias. Tudo que est\u00e1 disposto neste artigo possui alto \u00edndice de cobran\u00e7a.<\/p>\n\n\n\n<p>Desejo a voc\u00ea uma boa prova. Um grande abra\u00e7o.<\/p>\n\n\n\n<p>Leandro Ricardo M. Silveira<\/p>\n\n\n\n<p><strong>Instagram: <\/strong><a href=\"https:\/\/www.instagram.com\/leandro.rms12\/\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/www.instagram.com\/leandro.rms12\/<\/a><\/p>\n\n\n\n<p class=\"has-text-align-center has-medium-font-size\"><em><strong>Assinatura Anual Ilimitada*<\/strong><\/em><\/p>\n\n\n\n<p class=\"has-text-align-center\"><em>Prepare-se com o melhor material e com quem mais aprova em Concursos P\u00fablicos em todo o pa\u00eds. Assine agora a nossa Assinatura Anual e tenha acesso ilimitado* a todos os nossos cursos.<\/em><\/p>\n\n\n\n<p class=\"has-text-align-center has-light-green-cyan-background-color has-background\" style=\"font-size:clamp(14.642px, 0.915rem + ((1vw - 3.2px) * 0.721), 22px);px\"><strong>ASSINE AGORA<\/strong>&nbsp;\u2013&nbsp;<strong><a rel=\"noreferrer noopener\" href=\"https:\/\/www.estrategiaconcursos.com.br\/assinaturas\" target=\"_blank\">Assinatura Ilimitada<\/a><\/strong><\/p>\n\n\n\n<p class=\"has-text-align-center has-medium-font-size\"><strong><em><strong>Sistema de Quest\u00f5es<\/strong><\/em><\/strong><\/p>\n\n\n\n<p class=\"has-text-align-center\"><em>Estrat\u00e9gia Quest\u00f5es nasceu maior do que todos os concorrentes, com mais quest\u00f5es cadastradas e mais solu\u00e7\u00f5es por professores. Ent\u00e3o, confira e aproveite os descontos e b\u00f4nus imperd\u00edveis!<\/em><\/p>\n\n\n\n<p class=\"has-text-align-center has-vivid-green-cyan-background-color has-background\" style=\"font-size:clamp(14.642px, 0.915rem + ((1vw - 3.2px) * 0.721), 22px);px\"><strong>ASSINE AGORA \u2013&nbsp;<a href=\"https:\/\/questoes.estrategiaconcursos.com.br\/\" target=\"_blank\" rel=\"noreferrer noopener\">Sistema de Quest\u00f5es<\/a><\/strong><\/p>\n\n\n\n<p class=\"has-text-align-center has-medium-font-size\"><strong><em>Fique por dentro dos concursos em aberto<\/em><\/strong><\/p>\n\n\n\n<p class=\"has-text-align-center has-pale-cyan-blue-background-color has-background\" style=\"font-size:clamp(14.642px, 0.915rem + ((1vw - 3.2px) * 0.721), 22px);px\"><a rel=\"noreferrer noopener\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-abertos\/\" target=\"_blank\"><strong>CONCURSOS ABERTOS<\/strong><\/a><\/p>\n\n\n\n<p class=\"has-text-align-center has-medium-font-size\"><strong><em>As oportunidades previstas<\/em><\/strong><\/p>\n\n\n\n<p class=\"has-text-align-center has-pale-cyan-blue-background-color has-background\" style=\"font-size:clamp(14.642px, 0.915rem + ((1vw - 3.2px) * 0.721), 22px);px\"><a rel=\"noreferrer noopener\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-2021\/\" target=\"_blank\"><strong>CONCURSOS 2021<\/strong><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Veja as principais disposi\u00e7\u00f5es da Lei 11.107 sobre cons\u00f3rcios p\u00fablicos para concurso Pol\u00edcia Federal e n\u00e3o erre nenhuma quest\u00e3o sobre o tema Ol\u00e1, Estrategista. Tudo joia? Um dos assuntos cobrados em direito administrativo que causam grandes \u00edndices de erros nos candidatos \u00e9 o tema cons\u00f3rcios p\u00fablicos. Em virtude disso, dissecaremos nesse artigo tudo que voc\u00ea [&hellip;]<\/p>\n","protected":false},"author":1668,"featured_media":658531,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"post_tipo":"article","footnotes":""},"categories":[1988],"tags":[1248,220077],"tax_estado":[219964,219965,219966,219967,219968,219969,219963,219970,219971,219972,219973,219974,219975,219976,219977,219978,219979,219980,219981,219982,219983,219984,219985,219986,219987,219988,219989,219990],"class_list":["post-658530","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-policia","tag-concurso-pf","tag-consorcios-publicos","tax_estado-ac","tax_estado-al","tax_estado-am","tax_estado-ap","tax_estado-ba","tax_estado-ce","tax_estado-concursos-federais","tax_estado-df","tax_estado-es","tax_estado-go","tax_estado-ma","tax_estado-mg","tax_estado-ms","tax_estado-mt","tax_estado-pa","tax_estado-pb","tax_estado-pe","tax_estado-pi","tax_estado-pr","tax_estado-rj","tax_estado-rn","tax_estado-ro","tax_estado-rr","tax_estado-rs","tax_estado-sc","tax_estado-se","tax_estado-sp","tax_estado-to"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.2 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Resumo da Lei de Cons\u00f3rcios P\u00fablicos para concurso PF<\/title>\n<meta name=\"description\" content=\"Veja as principais disposi\u00e7\u00f5es da Lei 11.107 sobre cons\u00f3rcios p\u00fablicos para concurso PF e n\u00e3o erre nenhuma quest\u00e3o sobre o tema\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/consorcios-publicos-para-concurso-pf\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Resumo da Lei de Cons\u00f3rcios P\u00fablicos para concurso PF\" \/>\n<meta property=\"og:description\" content=\"Veja as principais disposi\u00e7\u00f5es da Lei 11.107 sobre cons\u00f3rcios p\u00fablicos para concurso PF e n\u00e3o erre nenhuma quest\u00e3o sobre o tema\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/consorcios-publicos-para-concurso-pf\/\" \/>\n<meta property=\"og:site_name\" content=\"Estrat\u00e9gia Concursos\" \/>\n<meta property=\"article:published_time\" content=\"2021-02-04T14:20:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-02-10T18:16:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/01\/27111727\/download-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"310\" \/>\n\t<meta property=\"og:image:height\" content=\"163\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Leandro Ricardo Machado da Silveira\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:site\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Leandro Ricardo Machado da Silveira\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"10 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/consorcios-publicos-para-concurso-pf\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/consorcios-publicos-para-concurso-pf\/\"},\"author\":{\"name\":\"Leandro Ricardo Machado da Silveira\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/c666a44fbce7e2e70009a9c13549267a\"},\"headline\":\"Resumo da Lei de Cons\u00f3rcios P\u00fablicos para concurso PF\",\"datePublished\":\"2021-02-04T14:20:00+00:00\",\"dateModified\":\"2021-02-10T18:16:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/consorcios-publicos-para-concurso-pf\/\"},\"wordCount\":2080,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/consorcios-publicos-para-concurso-pf\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/01\/27111727\/download-1.png\",\"keywords\":[\"concurso PF\",\"cons\u00f3rcios p\u00fablicos\"],\"articleSection\":[\"Policial (Agente, Escriv\u00e3o e Investigador)\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/consorcios-publicos-para-concurso-pf\/#respond\"]}],\"copyrightYear\":\"2021\",\"copyrightHolder\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/consorcios-publicos-para-concurso-pf\/\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/consorcios-publicos-para-concurso-pf\/\",\"name\":\"Resumo da Lei de Cons\u00f3rcios P\u00fablicos para concurso PF\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/consorcios-publicos-para-concurso-pf\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/consorcios-publicos-para-concurso-pf\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/01\/27111727\/download-1.png\",\"datePublished\":\"2021-02-04T14:20:00+00:00\",\"dateModified\":\"2021-02-10T18:16:28+00:00\",\"description\":\"Veja as principais disposi\u00e7\u00f5es da Lei 11.107 sobre cons\u00f3rcios p\u00fablicos para concurso PF e n\u00e3o erre nenhuma quest\u00e3o sobre o tema\",\"breadcrumb\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/consorcios-publicos-para-concurso-pf\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/consorcios-publicos-para-concurso-pf\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/consorcios-publicos-para-concurso-pf\/#primaryimage\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/01\/27111727\/download-1.png\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/01\/27111727\/download-1.png\",\"width\":310,\"height\":163},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/consorcios-publicos-para-concurso-pf\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Resumo da Lei de Cons\u00f3rcios P\u00fablicos para concurso PF\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"name\":\"Estrat\u00e9gia Concursos\",\"description\":\"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.\",\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\",\"name\":\"Estrat\u00e9gia Concursos\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"width\":230,\"height\":60,\"caption\":\"Estrat\u00e9gia Concursos\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/EstratConcursos\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/c666a44fbce7e2e70009a9c13549267a\",\"name\":\"Leandro Ricardo Machado da Silveira\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/6fb25994d16b9649838400aa459b16c1c83f558e0fd6ebebd16da0473908b291?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/6fb25994d16b9649838400aa459b16c1c83f558e0fd6ebebd16da0473908b291?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/6fb25994d16b9649838400aa459b16c1c83f558e0fd6ebebd16da0473908b291?s=96&d=mm&r=g\",\"caption\":\"Leandro Ricardo Machado da Silveira\"},\"description\":\"Engenheiro Aeron\u00e1utico, formado pela Universidade Federal de Uberl\u00e2ndia, possui MBA em Administra\u00e7\u00e3o e Finan\u00e7as Corporativas e aprovado nos concursos de Auditor Fiscal SEFAZ-SC e SEFAZ-GO.\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/leandro_vzthotmail-com\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Resumo da Lei de Cons\u00f3rcios P\u00fablicos para concurso PF","description":"Veja as principais disposi\u00e7\u00f5es da Lei 11.107 sobre cons\u00f3rcios p\u00fablicos para concurso PF e n\u00e3o erre nenhuma quest\u00e3o sobre o tema","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.estrategiaconcursos.com.br\/blog\/consorcios-publicos-para-concurso-pf\/","og_locale":"pt_BR","og_type":"article","og_title":"Resumo da Lei de Cons\u00f3rcios P\u00fablicos para concurso PF","og_description":"Veja as principais disposi\u00e7\u00f5es da Lei 11.107 sobre cons\u00f3rcios p\u00fablicos para concurso PF e n\u00e3o erre nenhuma quest\u00e3o sobre o tema","og_url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/consorcios-publicos-para-concurso-pf\/","og_site_name":"Estrat\u00e9gia Concursos","article_published_time":"2021-02-04T14:20:00+00:00","article_modified_time":"2021-02-10T18:16:28+00:00","og_image":[{"width":310,"height":163,"url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/01\/27111727\/download-1.png","type":"image\/png"}],"author":"Leandro Ricardo Machado da Silveira","twitter_card":"summary_large_image","twitter_creator":"@EstratConcursos","twitter_site":"@EstratConcursos","twitter_misc":{"Escrito por":"Leandro Ricardo Machado da Silveira","Est. tempo de leitura":"10 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/consorcios-publicos-para-concurso-pf\/#article","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/consorcios-publicos-para-concurso-pf\/"},"author":{"name":"Leandro Ricardo Machado da Silveira","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/c666a44fbce7e2e70009a9c13549267a"},"headline":"Resumo da Lei de Cons\u00f3rcios P\u00fablicos para concurso PF","datePublished":"2021-02-04T14:20:00+00:00","dateModified":"2021-02-10T18:16:28+00:00","mainEntityOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/consorcios-publicos-para-concurso-pf\/"},"wordCount":2080,"commentCount":0,"publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/consorcios-publicos-para-concurso-pf\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/01\/27111727\/download-1.png","keywords":["concurso PF","cons\u00f3rcios p\u00fablicos"],"articleSection":["Policial (Agente, Escriv\u00e3o e Investigador)"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/consorcios-publicos-para-concurso-pf\/#respond"]}],"copyrightYear":"2021","copyrightHolder":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/consorcios-publicos-para-concurso-pf\/","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/consorcios-publicos-para-concurso-pf\/","name":"Resumo da Lei de Cons\u00f3rcios P\u00fablicos para concurso PF","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/consorcios-publicos-para-concurso-pf\/#primaryimage"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/consorcios-publicos-para-concurso-pf\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/01\/27111727\/download-1.png","datePublished":"2021-02-04T14:20:00+00:00","dateModified":"2021-02-10T18:16:28+00:00","description":"Veja as principais disposi\u00e7\u00f5es da Lei 11.107 sobre cons\u00f3rcios p\u00fablicos para concurso PF e n\u00e3o erre nenhuma quest\u00e3o sobre o tema","breadcrumb":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/consorcios-publicos-para-concurso-pf\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/consorcios-publicos-para-concurso-pf\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/consorcios-publicos-para-concurso-pf\/#primaryimage","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/01\/27111727\/download-1.png","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/01\/27111727\/download-1.png","width":310,"height":163},{"@type":"BreadcrumbList","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/consorcios-publicos-para-concurso-pf\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.estrategiaconcursos.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Resumo da Lei de Cons\u00f3rcios P\u00fablicos para concurso PF"}]},{"@type":"WebSite","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","name":"Estrat\u00e9gia Concursos","description":"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.","publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization","name":"Estrat\u00e9gia Concursos","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","width":230,"height":60,"caption":"Estrat\u00e9gia Concursos"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/EstratConcursos"]},{"@type":"Person","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/c666a44fbce7e2e70009a9c13549267a","name":"Leandro Ricardo Machado da Silveira","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/6fb25994d16b9649838400aa459b16c1c83f558e0fd6ebebd16da0473908b291?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/6fb25994d16b9649838400aa459b16c1c83f558e0fd6ebebd16da0473908b291?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6fb25994d16b9649838400aa459b16c1c83f558e0fd6ebebd16da0473908b291?s=96&d=mm&r=g","caption":"Leandro Ricardo Machado da Silveira"},"description":"Engenheiro Aeron\u00e1utico, formado pela Universidade Federal de Uberl\u00e2ndia, possui MBA em Administra\u00e7\u00e3o e Finan\u00e7as Corporativas e aprovado nos concursos de Auditor Fiscal SEFAZ-SC e SEFAZ-GO.","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/leandro_vzthotmail-com\/"}]}},"_links":{"self":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/658530","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/users\/1668"}],"replies":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/comments?post=658530"}],"version-history":[{"count":3,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/658530\/revisions"}],"predecessor-version":[{"id":670147,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/658530\/revisions\/670147"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media\/658531"}],"wp:attachment":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media?parent=658530"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/categories?post=658530"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tags?post=658530"},{"taxonomy":"tax_estado","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tax_estado?post=658530"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}