{"id":658527,"date":"2021-01-27T11:53:56","date_gmt":"2021-01-27T14:53:56","guid":{"rendered":"https:\/\/blog-estrategia.mystagingwebsite.com\/blog\/?p=658527"},"modified":"2021-01-27T11:53:59","modified_gmt":"2021-01-27T14:53:59","slug":"cfc-locais-provas-procedimento-reembolso","status":"publish","type":"post","link":"https:\/\/www.estrategiaconcursos.com.br\/blog\/cfc-locais-provas-procedimento-reembolso\/","title":{"rendered":"CFC divulga os locais de provas e procedimento de reembolso"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">J\u00e1 est\u00e1 dispon\u00edvel a <strong>rela\u00e7\u00e3o com os locais de provas<\/strong> para realiza\u00e7\u00e3o do 2\u00ba Exame de Sufici\u00eancia de 2020 do Conselho Federal de Contabilidade (CFC). A etapa est\u00e1 prevista para ocorrer neste pr\u00f3ximo domingo, <strong>31 de dezembro<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Contudo, aqueles que se inscreveram para realizar a prova na cidade de <a href=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/27112148\/22_73383.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">Ribeir\u00e3o Preto\/SP<\/a> devem aguardar mais algumas horas para verificar seu local de exame. Isso porque, por conta das limita\u00e7\u00f5es decorrentes da pandemia, os ambientes est\u00e3o em processo de valida\u00e7\u00e3o.<\/p>\n\n\n\n<h2 class=\"has-text-align-center has-background has-medium-font-size wp-block-heading\" id=\"h-locais-de-provas-exame-cfc\" style=\"background-color:#eeeeee\"><a href=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/27112008\/28_709675.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">Locais de provas Exame CFC<\/a><\/h2>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-provas-cfc-em-manaus\">Provas CFC em Manaus<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Vale lembrar que as <strong>provas objetivas na cidade de Manaus foram canceladas<\/strong>, em virtude do momento atual no estado do Amazonas e das consequ\u00eancias da pandemia que impede a realiza\u00e7\u00e3o do exame.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para esses casos, o Conselho Federal de Contabilidade j\u00e1 disponibilizou a listagem dos inscritos que poder\u00e3o solicitar o reembolso da taxa ou optar por permanecer com a inscri\u00e7\u00e3o efetivada, para fins de participa\u00e7\u00e3o na 1\u00aa edi\u00e7\u00e3o do Exame de 2021.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O <strong>processo de reembolso deve ser feito at\u00e9 o dia 26 de fevereiro<\/strong>, atrav\u00e9s do <a href=\"https:\/\/concurso2.consulplan.net\/devolucao\/Login.aspx?key=164\" target=\"_blank\" rel=\"noreferrer noopener\">site do Consulplan<\/a>. Para tanto, ser\u00e1 necess\u00e1rio enviar todos os dados necess\u00e1rios para devolu\u00e7\u00e3o do valor pago a t\u00edtulo de inscri\u00e7\u00e3o.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">J\u00e1 a participa\u00e7\u00e3o na 1\u00aa edi\u00e7\u00e3o do Exame de 2021 ser\u00e1 garantida a todos os examinandos que constam na listagem, desde que n\u00e3o solicitem a devolu\u00e7\u00e3o da taxa, n\u00e3o sendo necess\u00e1rio realizar qualquer manifesta\u00e7\u00e3o ou procedimento espec\u00edfico.<\/p>\n\n\n\n<p class=\"has-text-align-center has-background has-medium-font-size wp-block-paragraph\" style=\"background-color:#eeeeee\"><a href=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/27112101\/24_1718206.pdf\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Listagem dos inscritos para reembolso<\/strong><\/a><\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-sobre-a-prova-do-exame-cfc\">Sobre a prova do Exame CFC<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">A prova objetiva do Exame CFC ser\u00e1 composta por<strong>\u00a050 quest\u00f5es<\/strong> <strong>de m\u00faltipla escolha<\/strong>, com quatro op\u00e7\u00f5es (A, B, C e D), valendo um ponto cada. As quest\u00f5es cobradas dos candidatos ao cargo de Bacharel em Ci\u00eancias Cont\u00e1beis abrangem os seguintes assuntos:<\/p>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-794e3cfa wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<ul class=\"wp-block-list\" id=\"block-38d4460b-cb87-4dcb-b229-8f8f3197e811\"><li><em>Contabilidade Geral<\/em><\/li><li><em>Contabilidade de Custos<\/em><\/li><li><em>Contabilidade Aplicada ao Setor P\u00fablico<\/em><\/li><li><em>Contabilidade Gerencial<\/em><\/li><li><em>Controladoria<\/em><\/li><li><em>No\u00e7\u00f5es de Direito e Legisla\u00e7\u00e3o Aplicada<\/em><\/li><li><em>Matem\u00e1tica Financeira e Estat\u00edstica<\/em><\/li><\/ul>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<ul class=\"wp-block-list\" id=\"block-38d4460b-cb87-4dcb-b229-8f8f3197e811\"><li><em>Teoria da Contabilidade<\/em><\/li><li><em>Legisla\u00e7\u00e3o e \u00c9tica Profissional<\/em><\/li><li><em>Princ\u00edpios de Contabilidade e Normas Brasileiras de Contabilidade<\/em><\/li><li><em>Audit\u00f3ria Cont\u00e1bil<\/em><\/li><li><em>Per\u00edcia Cont\u00e1bil<\/em><\/li><li><em>L\u00edngua Portuguesa Aplicada<\/em><\/li><\/ul>\n<\/div>\n<\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Ser\u00e1 considerado aprovado aquele que acertar, no m\u00ednimo, 50% do total das quest\u00f5es. Ou seja, 25 pontos. Em hip\u00f3tese alguma, devido \u00e0 anula\u00e7\u00e3o de qualquer quest\u00e3o, a prova deixar\u00e1 de valer 50 pontos em sua totalidade.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/01\/27115020\/coruja-300x212-1-1.png\" alt=\"cfc locais\" class=\"wp-image-658580\" width=\"150\" height=\"106\"\/><\/figure><\/div>\n\n\n\n<p class=\"has-text-align-center has-background has-medium-font-size wp-block-paragraph\" style=\"background-color:#eeeeee\"><strong>Saiba mais: <a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/exame-cfc\/\" target=\"_blank\" rel=\"noreferrer noopener\">Exame CFC<\/a><\/strong><\/p>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<div class=\"container\" id=\"boxes\">\n  <div class=\"row\">\n\n    <div class=\"col-sm\">\n      <div class=\"banner-adm\" id=\"box-assinatura\">\n        <h3 class=\"titulo-assinatura\">Carreiras Administrativas<\/h3>\n        <p class=\"subtitulo-assinatura\">Estude conosco<\/p>\n        <div class=\"box-botao\">\n          <a class=\"btn-assinatura\" target=\"_blank\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/cursos\/\" role=\"button\" rel=\"noopener noreferrer\">Conhe\u00e7a os cursos<\/a>\n        <\/div>\n      <\/div>\n      <p class=\"texto-auxiliar\">Prepare-se com o melhor material e com quem mais aprova em Concursos P\u00fablicos em todo o pa\u00eds. Assine agora a nossa Assinatura Anual e tenha acesso ilimitado* a todos os nossos cursos.<\/p>\n    <\/div>\n\n  <\/div>\n<\/div>\n\n\n\n<div class=\"container\" id=\"boxes\">\n  <div class=\"row\">\n\n    <div class=\"col-sm\">\n      <div class=\"estrategia\" id=\"box-assinatura\">\n        <h3 class=\"titulo-assinatura\">Assinatura Ilimitada<\/h3>\n        <p class=\"subtitulo-assinatura\">Assinatura Anual Ilimitada*<\/p>\n        <div class=\"box-botao\">\n          <a class=\"btn-assinatura\" target=\"_blank\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/assinaturas\/\" role=\"button\" rel=\"noopener noreferrer\">ASSINE AGORA<\/a>\n        <\/div>\n      <\/div>\n      <p class=\"texto-auxiliar\">Prepare-se com o melhor material e com quem mais aprova em Concursos P\u00fablicos em todo o pa\u00eds. Assine agora a nossa Assinatura Anual e tenha acesso ilimitado* a todos os nossos cursos.<\/p>\n    <\/div>\n\n    <div class=\"col-sm\">\n      <div class=\"questoes\" id=\"box-assinatura\">\n        <h3 class=\"titulo-assinatura\">Sistema de Quest\u00f5es<\/h3>\n        <p class=\"subtitulo-assinatura\">Assinatura Ilimitada*\n<\/p>\n        <div class=\"box-botao\">\n          <a class=\"btn-assinatura\" target=\"_blank\" href=\"https:\/\/questoes.estrategiaconcursos.com.br\/\" role=\"button\" rel=\"noopener noreferrer\">ASSINE AGORA<\/a>\n        <\/div>\n      <\/div>\n      <p class=\"texto-auxiliar\">Estrat\u00e9gia Quest\u00f5es nasceu maior do que todos os concorrentes, com mais quest\u00f5es cadastradas e mais solu\u00e7\u00f5es por professores. Clique no link e aproveite os descontos e b\u00f4nus imperd\u00edveis!<\/p>\n    <\/div>\n  <\/div>\n<\/div>\n\n\n\n<div class=\"container\" id=\"boxes\">\n  <div class=\"row\">\n\n    <div class=\"col-sm\" id=\"boxes-concursos\">\n      <div style=\"background-color: #005DAD;\" class=\"conteudo-concursos\" id=\"box-concursos\">\n        <h3 class=\"titulo-assinatura\">Concursos Abertos<\/h3>\n        <p class=\"subtitulo-assinatura\">mais de 15 mil vagas<\/p>\n        <div class=\"box-botao\">\n          <a class=\"btn-assinatura\" target=\"_blank\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-abertos\/\" role=\"button\" rel=\"noopener noreferrer\">Conhe\u00e7a Agora<\/a>\n        <\/div>\n      <\/div>\n    <\/div>\n\n    <div class=\"col-sm\" id=\"boxes-concursos\">\n      <div style=\"background-color: #419FF0;\" class=\"conteudo-concursos\" id=\"box-concursos\">\n        <h3 class=\"titulo-assinatura\">Concursos 2021<\/h3>\n        <p class=\"subtitulo-assinatura\">mais de 17 mil vagas<\/p>\n        <div class=\"box-botao\">\n          <a class=\"btn-assinatura\" target=\"_blank\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-2021\/\" role=\"button\" rel=\"noopener noreferrer\">Conhe\u00e7a Agora<\/a>\n        <\/div>\n      <\/div>\n    <\/div>\n\n  <\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>J\u00e1 est\u00e1 dispon\u00edvel a rela\u00e7\u00e3o com os locais de provas para realiza\u00e7\u00e3o do 2\u00ba Exame de Sufici\u00eancia de 2020 do Conselho Federal de Contabilidade (CFC). A etapa est\u00e1 prevista para ocorrer neste pr\u00f3ximo domingo, 31 de dezembro. Contudo, aqueles que se inscreveram para realizar a prova na cidade de Ribeir\u00e3o Preto\/SP devem aguardar mais algumas [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":410886,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"post_tipo":"news","footnotes":""},"categories":[220015],"tags":[],"tax_estado":[219963],"class_list":["post-658527","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cfc","tax_estado-concursos-federais"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>CFC divulga os locais de provas e procedimento de reembolso<\/title>\n<meta name=\"description\" content=\"CFC divulga os locais de provas para 2\u00ba Exame de Sufici\u00eancia de 2020 e procedimento de reembolso para os inscritos da cidade de Manaus.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blog-estrategia.mystagingwebsite.com\/cfc-locais-provas-procedimento-reembolso\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"CFC divulga os locais de provas e procedimento de reembolso\" \/>\n<meta property=\"og:description\" content=\"CFC divulga os locais de provas para 2\u00ba Exame de Sufici\u00eancia de 2020 e procedimento de reembolso para os inscritos da cidade de Manaus.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blog-estrategia.mystagingwebsite.com\/cfc-locais-provas-procedimento-reembolso\/\" \/>\n<meta property=\"og:site_name\" content=\"Estrat\u00e9gia Concursos\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/EstrategiaConcursos\" \/>\n<meta property=\"article:published_time\" content=\"2021-01-27T14:53:56+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-01-27T14:53:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2019\/08\/19115911\/CFC.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"628\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Coordena\u00e7\u00e3o\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:site\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Coordena\u00e7\u00e3o\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/blog-estrategia.mystagingwebsite.com\\\/cfc-locais-provas-procedimento-reembolso\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog-estrategia.mystagingwebsite.com\\\/cfc-locais-provas-procedimento-reembolso\\\/\"},\"author\":{\"name\":\"Coordena\u00e7\u00e3o\",\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/#\\\/schema\\\/person\\\/b4a388c97673c5f483d72185668afa1f\"},\"headline\":\"CFC divulga os locais de provas e procedimento de reembolso\",\"datePublished\":\"2021-01-27T14:53:56+00:00\",\"dateModified\":\"2021-01-27T14:53:59+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/blog-estrategia.mystagingwebsite.com\\\/cfc-locais-provas-procedimento-reembolso\\\/\"},\"wordCount\":562,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/blog-estrategia.mystagingwebsite.com\\\/cfc-locais-provas-procedimento-reembolso\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dhg1h5j42swfq.cloudfront.net\\\/2019\\\/08\\\/19115911\\\/CFC.jpg\",\"articleSection\":[\"CFC\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/blog-estrategia.mystagingwebsite.com\\\/cfc-locais-provas-procedimento-reembolso\\\/#respond\"]}],\"copyrightYear\":\"2021\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/blog-estrategia.mystagingwebsite.com\\\/cfc-locais-provas-procedimento-reembolso\\\/\",\"url\":\"https:\\\/\\\/blog-estrategia.mystagingwebsite.com\\\/cfc-locais-provas-procedimento-reembolso\\\/\",\"name\":\"CFC divulga os locais de provas e procedimento de reembolso\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/blog-estrategia.mystagingwebsite.com\\\/cfc-locais-provas-procedimento-reembolso\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/blog-estrategia.mystagingwebsite.com\\\/cfc-locais-provas-procedimento-reembolso\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dhg1h5j42swfq.cloudfront.net\\\/2019\\\/08\\\/19115911\\\/CFC.jpg\",\"datePublished\":\"2021-01-27T14:53:56+00:00\",\"dateModified\":\"2021-01-27T14:53:59+00:00\",\"description\":\"CFC divulga os locais de provas para 2\u00ba Exame de Sufici\u00eancia de 2020 e procedimento de reembolso para os inscritos da cidade de Manaus.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blog-estrategia.mystagingwebsite.com\\\/cfc-locais-provas-procedimento-reembolso\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/blog-estrategia.mystagingwebsite.com\\\/cfc-locais-provas-procedimento-reembolso\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/blog-estrategia.mystagingwebsite.com\\\/cfc-locais-provas-procedimento-reembolso\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dhg1h5j42swfq.cloudfront.net\\\/2019\\\/08\\\/19115911\\\/CFC.jpg\",\"contentUrl\":\"https:\\\/\\\/dhg1h5j42swfq.cloudfront.net\\\/2019\\\/08\\\/19115911\\\/CFC.jpg\",\"width\":1200,\"height\":628,\"caption\":\"Provas Exame CFC\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blog-estrategia.mystagingwebsite.com\\\/cfc-locais-provas-procedimento-reembolso\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"CFC divulga os locais de provas e procedimento de reembolso\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/\",\"name\":\"Estrat\u00e9gia Concursos\",\"description\":\"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/#organization\",\"name\":\"Estrat\u00e9gia Concursos\",\"url\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dhg1h5j42swfq.cloudfront.net\\\/2025\\\/06\\\/03203428\\\/logo_concursos-1.jpg\",\"contentUrl\":\"https:\\\/\\\/dhg1h5j42swfq.cloudfront.net\\\/2025\\\/06\\\/03203428\\\/logo_concursos-1.jpg\",\"width\":230,\"height\":60,\"caption\":\"Estrat\u00e9gia Concursos\"},\"image\":{\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/EstratConcursos\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/#\\\/schema\\\/person\\\/b4a388c97673c5f483d72185668afa1f\",\"name\":\"Coordena\u00e7\u00e3o\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b720319e4c9a967eb58678d110f4fe35452fc5d5f97b202bac7b8acceb18c6ad?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b720319e4c9a967eb58678d110f4fe35452fc5d5f97b202bac7b8acceb18c6ad?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b720319e4c9a967eb58678d110f4fe35452fc5d5f97b202bac7b8acceb18c6ad?s=96&d=mm&r=g\",\"caption\":\"Coordena\u00e7\u00e3o\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/EstrategiaConcursos\",\"https:\\\/\\\/x.com\\\/EstratConcursos\"],\"url\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/author\\\/estrategia2013\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"CFC divulga os locais de provas e procedimento de reembolso","description":"CFC divulga os locais de provas para 2\u00ba Exame de Sufici\u00eancia de 2020 e procedimento de reembolso para os inscritos da cidade de Manaus.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blog-estrategia.mystagingwebsite.com\/cfc-locais-provas-procedimento-reembolso\/","og_locale":"pt_BR","og_type":"article","og_title":"CFC divulga os locais de provas e procedimento de reembolso","og_description":"CFC divulga os locais de provas para 2\u00ba Exame de Sufici\u00eancia de 2020 e procedimento de reembolso para os inscritos da cidade de Manaus.","og_url":"https:\/\/blog-estrategia.mystagingwebsite.com\/cfc-locais-provas-procedimento-reembolso\/","og_site_name":"Estrat\u00e9gia Concursos","article_author":"https:\/\/www.facebook.com\/EstrategiaConcursos","article_published_time":"2021-01-27T14:53:56+00:00","article_modified_time":"2021-01-27T14:53:59+00:00","og_image":[{"width":1200,"height":628,"url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2019\/08\/19115911\/CFC.jpg","type":"image\/jpeg"}],"author":"Coordena\u00e7\u00e3o","twitter_card":"summary_large_image","twitter_creator":"@EstratConcursos","twitter_site":"@EstratConcursos","twitter_misc":{"Escrito por":"Coordena\u00e7\u00e3o","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/blog-estrategia.mystagingwebsite.com\/cfc-locais-provas-procedimento-reembolso\/#article","isPartOf":{"@id":"https:\/\/blog-estrategia.mystagingwebsite.com\/cfc-locais-provas-procedimento-reembolso\/"},"author":{"name":"Coordena\u00e7\u00e3o","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/b4a388c97673c5f483d72185668afa1f"},"headline":"CFC divulga os locais de provas e procedimento de reembolso","datePublished":"2021-01-27T14:53:56+00:00","dateModified":"2021-01-27T14:53:59+00:00","mainEntityOfPage":{"@id":"https:\/\/blog-estrategia.mystagingwebsite.com\/cfc-locais-provas-procedimento-reembolso\/"},"wordCount":562,"commentCount":0,"publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"image":{"@id":"https:\/\/blog-estrategia.mystagingwebsite.com\/cfc-locais-provas-procedimento-reembolso\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2019\/08\/19115911\/CFC.jpg","articleSection":["CFC"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/blog-estrategia.mystagingwebsite.com\/cfc-locais-provas-procedimento-reembolso\/#respond"]}],"copyrightYear":"2021","copyrightHolder":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/blog-estrategia.mystagingwebsite.com\/cfc-locais-provas-procedimento-reembolso\/","url":"https:\/\/blog-estrategia.mystagingwebsite.com\/cfc-locais-provas-procedimento-reembolso\/","name":"CFC divulga os locais de provas e procedimento de reembolso","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blog-estrategia.mystagingwebsite.com\/cfc-locais-provas-procedimento-reembolso\/#primaryimage"},"image":{"@id":"https:\/\/blog-estrategia.mystagingwebsite.com\/cfc-locais-provas-procedimento-reembolso\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2019\/08\/19115911\/CFC.jpg","datePublished":"2021-01-27T14:53:56+00:00","dateModified":"2021-01-27T14:53:59+00:00","description":"CFC divulga os locais de provas para 2\u00ba Exame de Sufici\u00eancia de 2020 e procedimento de reembolso para os inscritos da cidade de Manaus.","breadcrumb":{"@id":"https:\/\/blog-estrategia.mystagingwebsite.com\/cfc-locais-provas-procedimento-reembolso\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blog-estrategia.mystagingwebsite.com\/cfc-locais-provas-procedimento-reembolso\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/blog-estrategia.mystagingwebsite.com\/cfc-locais-provas-procedimento-reembolso\/#primaryimage","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2019\/08\/19115911\/CFC.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2019\/08\/19115911\/CFC.jpg","width":1200,"height":628,"caption":"Provas Exame CFC"},{"@type":"BreadcrumbList","@id":"https:\/\/blog-estrategia.mystagingwebsite.com\/cfc-locais-provas-procedimento-reembolso\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.estrategiaconcursos.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"CFC divulga os locais de provas e procedimento de reembolso"}]},{"@type":"WebSite","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","name":"Estrat\u00e9gia Concursos","description":"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.","publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization","name":"Estrat\u00e9gia Concursos","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","width":230,"height":60,"caption":"Estrat\u00e9gia Concursos"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/EstratConcursos"]},{"@type":"Person","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/b4a388c97673c5f483d72185668afa1f","name":"Coordena\u00e7\u00e3o","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/b720319e4c9a967eb58678d110f4fe35452fc5d5f97b202bac7b8acceb18c6ad?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b720319e4c9a967eb58678d110f4fe35452fc5d5f97b202bac7b8acceb18c6ad?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b720319e4c9a967eb58678d110f4fe35452fc5d5f97b202bac7b8acceb18c6ad?s=96&d=mm&r=g","caption":"Coordena\u00e7\u00e3o"},"sameAs":["https:\/\/www.facebook.com\/EstrategiaConcursos","https:\/\/x.com\/EstratConcursos"],"url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/estrategia2013\/"}]}},"_links":{"self":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/658527","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/comments?post=658527"}],"version-history":[{"count":0,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/658527\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media\/410886"}],"wp:attachment":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media?parent=658527"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/categories?post=658527"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tags?post=658527"},{"taxonomy":"tax_estado","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tax_estado?post=658527"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}