{"id":615215,"date":"2020-11-23T18:00:44","date_gmt":"2020-11-23T21:00:44","guid":{"rendered":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?p=615215"},"modified":"2021-01-22T17:05:19","modified_gmt":"2021-01-22T20:05:19","slug":"prova-de-titulos-qual-e-o-impacto-da-etapa-na-sua-aprovacao","status":"publish","type":"post","link":"https:\/\/www.estrategiaconcursos.com.br\/blog\/prova-de-titulos-qual-e-o-impacto-da-etapa-na-sua-aprovacao\/","title":{"rendered":"Prova de t\u00edtulos: qual \u00e9 o impacto da etapa na sua aprova\u00e7\u00e3o?"},"content":{"rendered":"\n<p><em>Entenda como voc\u00ea pode obter pontua\u00e7\u00f5es adicionais no seu certame para melhorar a sua classifica\u00e7\u00e3o final e conquistar a sua aprova\u00e7\u00e3o!<\/em><\/p>\n\n\n\n<p>As provas objetivas e discursivas s\u00e3o as fases mais conhecidas e mais comentadas no universo dos concursos p\u00fablicos: elas s\u00e3o respons\u00e1veis por selecionar os candidatos para avan\u00e7arem para as pr\u00f3ximas etapas dos certames.&nbsp;<\/p>\n\n\n\n<p>Contudo, vemos que muitos alunos t\u00eam d\u00favidas a respeito dos concursos p\u00fablicos que apresentam a prova de t\u00edtulos como uma fase para a sele\u00e7\u00e3o de candidatos. <\/p>\n\n\n\n<p>Por isso, no post de hoje, voc\u00ea vai entender <strong>como as provas de t\u00edtulos funcionam<\/strong> e como voc\u00ea pode obter pontos preciosos para a sua aprova\u00e7\u00e3o. :) Vamos l\u00e1?<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-1-como-funciona-a-prova-de-t-tulos\">1) Como funciona a prova de t\u00edtulos?<\/h2>\n\n\n\n<p>A prova de t\u00edtulos \u00e9 uma etapa realizada em muitos concursos p\u00fablicos, a partir de uma previs\u00e3o constitucional que d\u00e1 a liberdade para que a Administra\u00e7\u00e3o P\u00fablica realize essa fase nos seus processos de sele\u00e7\u00e3o de pessoal. Veja:<\/p>\n\n\n\n<p>&nbsp;<em>&nbsp;Art. 37. A administra\u00e7\u00e3o p\u00fablica direta e indireta de qualquer dos Poderes da Uni\u00e3o, dos Estados, do Distrito Federal e dos Munic\u00edpios obedecer\u00e1 aos princ\u00edpios de legalidade, impessoalidade, moralidade, publicidade e efici\u00eancia e, tamb\u00e9m, ao seguinte:&nbsp;<\/em><\/p>\n\n\n\n<p><em>[&#8230;]<\/em><\/p>\n\n\n\n<p><em>II &#8211; a investidura em cargo ou emprego p\u00fablico depende de aprova\u00e7\u00e3o pr\u00e9via em concurso p\u00fablico de provas ou de provas e t\u00edtulos, de acordo com a natureza e a complexidade do cargo ou emprego, na forma prevista em lei, ressalvadas as nomea\u00e7\u00f5es para cargo em comiss\u00e3o declarado em lei de livre nomea\u00e7\u00e3o e exonera\u00e7\u00e3o; (Constitui\u00e7\u00e3o Federal de 1988)<\/em><\/p>\n\n\n\n<p>Dessa forma, as provas de t\u00edtulos valorizam o candidato que busca uma qualifica\u00e7\u00e3o al\u00e9m da m\u00ednima exigida em edital para ocupar aquele cargo espec\u00edfico que ser\u00e1 disputado no concurso p\u00fablico. Em geral, o cen\u00e1rio mais comum \u00e9 vermos as provas de t\u00edtulos serem exigidas para cargos de n\u00edvel superior.&nbsp;<\/p>\n\n\n\n<p>As provas de t\u00edtulos s\u00e3o etapas classificat\u00f3rias nos certames e, portanto, <strong>t\u00eam um impacto significativo na classifica\u00e7\u00e3o final dos candidatos<\/strong> para um determinado cargo. Elas costumam ocorrer ap\u00f3s as fases objetivas e discursivas, dependendo do concurso em quest\u00e3o.&nbsp;<\/p>\n\n\n\n<p>O edital definir\u00e1 uma data na qual os candidatos, j\u00e1 aprovados em fases anteriores, dever\u00e3o apresentar os t\u00edtulos para obterem a pontua\u00e7\u00e3o correspondente \u00e0s suas qualifica\u00e7\u00f5es. Dessa forma, \u00e9 importante verificar nos editais:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>o peso vinculado \u00e0 etapa de t\u00edtulos no certame;<\/li><li>a pontua\u00e7\u00e3o atribu\u00edda a cada n\u00edvel de qualifica\u00e7\u00e3o;<\/li><li>os prazos e os requisitos para envio dos documentos para a banca examinadora.<\/li><\/ul>\n\n\n\n<p>Cabe ressaltar que as bancas podem exigir c\u00f3pias autenticadas dos t\u00edtulos apresentados para valid\u00e1-los como parte integrante do certame, bem como exigir a tradu\u00e7\u00e3o juramentada em caso de documentos obtidos no exterior.&nbsp;<\/p>\n\n\n\n<p>Ap\u00f3s o prazo de entrega da documenta\u00e7\u00e3o, a banca examinadora apresentar\u00e1 a lista dos candidatos em ordem de pontua\u00e7\u00e3o, j\u00e1 considerando os t\u00edtulos recebidos e aprovados para a finalidade do concurso.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-2-poss-vel-ser-aprovado-em-um-certame-sem-apresentar-t-tulos-para-a-banca-examinadora\">2) \u00c9 poss\u00edvel ser aprovado em um certame sem apresentar t\u00edtulos para a banca examinadora?<\/h2>\n\n\n\n<p>Sim, \u00e9 poss\u00edvel. A prova de t\u00edtulos n\u00e3o \u00e9 uma etapa obrigat\u00f3ria nos concursos em geral (Tribunais, Fiscal, etc) e serve como fase <strong>classificat\u00f3ria <\/strong>para que a Administra\u00e7\u00e3o P\u00fablica possa selecionar profissionais que, al\u00e9m do bom desempenho nas outras provas, tamb\u00e9m tenham uma qualifica\u00e7\u00e3o adicional.&nbsp;<\/p>\n\n\n\n<p>Contudo, ao longo dos \u00faltimos anos, temos visto o crescimento exponencial da concorr\u00eancia de candidatos por vaga nos concursos p\u00fablicos: isso significa que ser aprovado est\u00e1 cada vez mais dif\u00edcil, sobretudo devido \u00e0 alta procura pelo servi\u00e7o p\u00fablico e tamb\u00e9m porque muitos \u00f3rg\u00e3os t\u00eam liberado, por quest\u00f5es financeiras e or\u00e7ament\u00e1rias, quantidades menores de vagas efetivas.&nbsp;<\/p>\n\n\n\n<p>Nesse contexto, entendemos que a prova de t\u00edtulos \u00e9 um diferencial que <strong>pode colocar ou retirar um candidato da classifica\u00e7\u00e3o dentro do n\u00famero de vagas de um certame<\/strong>. Por isso, temos visto um grande aumento na quantidade de alunos que buscam cursar uma p\u00f3s-gradua\u00e7\u00e3o, por exemplo, como recurso para se destacar em rela\u00e7\u00e3o \u00e0 concorr\u00eancia nas etapas dos concursos p\u00fablicos na atualidade.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-3-como-s-o-atribu-dos-os-pontos-na-prova-de-t-tulos\">3) Como s\u00e3o atribu\u00eddos os pontos na prova de t\u00edtulos?<\/h2>\n\n\n\n<p>A pontua\u00e7\u00e3o na prova de t\u00edtulos \u00e9 atribu\u00edda <strong>de acordo com o n\u00edvel de qualifica\u00e7\u00e3o obtida pelo candidato<\/strong>. Assim, quanto maior for a titula\u00e7\u00e3o, maior tende a ser a quantidade de pontos recebidos ap\u00f3s a apresenta\u00e7\u00e3o dos documentos.&nbsp;<\/p>\n\n\n\n<p>Para exemplificar esse ponto, creio que \u00e9 importante vermos um caso real! Veja a prova de t\u00edtulos aplicada no concurso para Consultor-T\u00e9cnico Legislativo da C\u00e2mara Legislativa do Distrito Federal (CLDF):<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/lh3.googleusercontent.com\/cySbCgwzmFxHexFP1f_GybLncyBuR8du24zPbZMqR3QE2ydjK6dWSSAwBFkypRRIHZXfREzSA3OFOjuYdvHR0UqU9HVbBpehyOjVEphzPGnCwxh4uXRToqXyX3CcRVS5-k15omZs\" alt=\"\" \/><\/figure>\n\n\n\n<p>No caso do concurso em quest\u00e3o, a apresenta\u00e7\u00e3o de dois ou mais certificados de p\u00f3s-gradua\u00e7\u00e3o, por exemplo, n\u00e3o faria diferen\u00e7a na pontua\u00e7\u00e3o dos candidatos. Contudo, existem tamb\u00e9m certames que atribuem uma margem de pontos, como por exemplo: 0,75 ponto caso seja apresentado 1 certificado de p\u00f3s e 1,5 pontos se o candidato tiver 2 certificados de p\u00f3s-gradua\u00e7\u00e3o. Essa decis\u00e3o depende do \u00f3rg\u00e3o e tamb\u00e9m do edital definido para o certame.&nbsp;<\/p>\n\n\n\n<p>Em rela\u00e7\u00e3o aos cursos de p\u00f3s-gradua\u00e7\u00e3o, vale destacar que a carga hor\u00e1ria m\u00ednima exigida pelos concursos p\u00fablicos para que o certificado seja reconhecido \u00e9 de 360 horas totais. Ademais, os concursos <strong>aceitam cursos de p\u00f3s-gradua\u00e7\u00e3o realizados na modalidade \u00e0 dist\u00e2ncia, <\/strong>desde que sejam registrados e reconhecidos pelo MEC. :)&nbsp;<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-4-qual-a-diferen-a-que-a-prova-de-t-tulos-pode-fazer-na-classifica-o-final-no-concurso\">4) Qual \u00e9 a diferen\u00e7a que a prova de t\u00edtulos pode fazer na classifica\u00e7\u00e3o final no concurso?<\/h2>\n\n\n\n<p>Ao longo das nossas an\u00e1lises dos resultados obtidos pelos alunos nos mais diversos concursos p\u00fablicos, verificamos que a prova de t\u00edtulos pode fazer aquela diferen\u00e7a essencial para que o candidato esteja dentro do n\u00famero de vagas efetivas do certame.&nbsp;<\/p>\n\n\n\n<p>No caso de alunos aprovados em cadastro reserva, os t\u00edtulos tamb\u00e9m ajudam a melhorar a posi\u00e7\u00e3o obtida e, no final das contas, isso pode significar a contrata\u00e7\u00e3o ou n\u00e3o por parte do \u00f3rg\u00e3o p\u00fablico. Hoje em dia, a convoca\u00e7\u00e3o do cadastro reserva \u00e9 uma a\u00e7\u00e3o bem comum por parte das organiza\u00e7\u00f5es p\u00fablicas e, assim, ter uma boa classifica\u00e7\u00e3o, mesmo em CR, pode fazer toda a diferen\u00e7a para a vida futura do candidato.&nbsp;<\/p>\n\n\n\n<p>Como exemplo, vamos ver o cen\u00e1rio apresentado pela prova da CLDF para o cargo de Consultor T\u00e9cnico-Legislativo na categoria Administrador. O certame ofereceu 4 vagas efetivas para esse cargo + a forma\u00e7\u00e3o de cadastro-reserva. O candidato aprovado em 4o lugar apresentou um t\u00edtulo de p\u00f3s-gradua\u00e7\u00e3o e obteve 2 pontos na sua nota final. Caso n\u00e3o tivesse apresentado esse documento, ele teria ca\u00eddo para a quinta posi\u00e7\u00e3o do certame, ou seja, <strong>n\u00e3o seria aprovado dentro do n\u00famero de vagas efetivas oferecidas pelo concurso<\/strong>.&nbsp;<\/p>\n\n\n\n<p>Viu como a prova de t\u00edtulos pode ser crucial para a sua classifica\u00e7\u00e3o em um concurso p\u00fablico?&nbsp;<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-5-qual-a-melhor-forma-de-realizar-uma-p-s-gradua-o-e-pontuar-na-prova-de-t-tulos\">5) Qual \u00e9 a melhor forma de realizar uma p\u00f3s-gradua\u00e7\u00e3o e pontuar na prova de t\u00edtulos?<\/h2>\n\n\n\n<p>Aqui no Estrat\u00e9gia, n\u00f3s sabemos que a grande maioria dos nossos alunos tem um tempo limitado para realizar o seu estudo para os concursos p\u00fablicos. No entanto, muitas pessoas t\u00eam essa preocupa\u00e7\u00e3o com a prova de t\u00edtulos e precisam realizar uma p\u00f3s-gradua\u00e7\u00e3o, sem deixar os estudos para concursos de lado.&nbsp;<\/p>\n\n\n\n<p>Por isso, n\u00f3s nos unimos \u00e0 Faculdade Unyleya, refer\u00eancia em ensino superior no nosso pa\u00eds, para desenvolver os nossos programas de p\u00f3s-gradua\u00e7\u00e3o. S\u00e3o 14 programas dispon\u00edveis, divididos em duas \u00e1reas principais: <strong>carreiras p\u00fablicas em geral e carreiras jur\u00eddicas<\/strong>.\u00a0<\/p>\n\n\n\n<p>Todos os cursos s\u00e3o reconhecidos pelo MEC e s\u00e3o desenvolvidos no formato que voc\u00ea j\u00e1 conhece e confia: videoaulas, PDFs completos e acesso ao f\u00f3rum de d\u00favidas para contato personalizado com a nossa equipe pedag\u00f3gica!&nbsp;<\/p>\n\n\n\n<p>Para conhecer os nossos cursos de p\u00f3s-gradua\u00e7\u00e3o, \u00e9 s\u00f3 <a href=\"https:\/\/posestrategia.unyleya.edu.br\/\" target=\"_blank\" rel=\"noreferrer noopener\">clicar aqui<\/a>.&nbsp;<\/p>\n\n\n\n<p>Deixo aqui tamb\u00e9m um convite para que voc\u00ea nos acompanhe no <a href=\"http:\/\/instagram.com\/estrategiaposgraduacao\">Instagram da p\u00f3s-gradua\u00e7\u00e3o<\/a>! Estamos produzindo conte\u00fados incr\u00edveis para te auxiliar na sua jornada de estudos e no seu aprimoramento profissional!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Entenda como voc\u00ea pode obter pontua\u00e7\u00f5es adicionais no seu certame para melhorar a sua classifica\u00e7\u00e3o final e conquistar a sua aprova\u00e7\u00e3o! As provas objetivas e discursivas s\u00e3o as fases mais conhecidas e mais comentadas no universo dos concursos p\u00fablicos: elas s\u00e3o respons\u00e1veis por selecionar os candidatos para avan\u00e7arem para as pr\u00f3ximas etapas dos certames.&nbsp; Contudo, [&hellip;]<\/p>\n","protected":false},"author":1432,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"post_tipo":"article","footnotes":""},"categories":[1],"tags":[66625,66626,67301],"tax_estado":[],"class_list":["post-615215","post","type-post","status-publish","format-standard","hentry","category-cursos-e-concursos","tag-pos-graduacao-a-distancia","tag-pos-graduacao-ead","tag-prova-de-titulos"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.2 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Prova de t\u00edtulos: qual \u00e9 o impacto da etapa na sua aprova\u00e7\u00e3o?<\/title>\n<meta name=\"description\" content=\"Saiba como a prova de t\u00edtulos nos concursos p\u00fablicos pode impactar a sua aprova\u00e7\u00e3o. Entenda como funciona a pontua\u00e7\u00e3o obtida pelos candidatos...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/prova-de-titulos-qual-e-o-impacto-da-etapa-na-sua-aprovacao\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Prova de t\u00edtulos: qual \u00e9 o impacto da etapa na sua aprova\u00e7\u00e3o?\" \/>\n<meta property=\"og:description\" content=\"Saiba como a prova de t\u00edtulos nos concursos p\u00fablicos pode impactar a sua aprova\u00e7\u00e3o. Entenda como funciona a pontua\u00e7\u00e3o obtida pelos candidatos...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/prova-de-titulos-qual-e-o-impacto-da-etapa-na-sua-aprovacao\/\" \/>\n<meta property=\"og:site_name\" content=\"Estrat\u00e9gia Concursos\" \/>\n<meta property=\"article:published_time\" content=\"2020-11-23T21:00:44+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-01-22T20:05:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/lh3.googleusercontent.com\/cySbCgwzmFxHexFP1f_GybLncyBuR8du24zPbZMqR3QE2ydjK6dWSSAwBFkypRRIHZXfREzSA3OFOjuYdvHR0UqU9HVbBpehyOjVEphzPGnCwxh4uXRToqXyX3CcRVS5-k15omZs\" \/>\n<meta name=\"author\" content=\"J\u00falia Branco\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:site\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"J\u00falia Branco\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/prova-de-titulos-qual-e-o-impacto-da-etapa-na-sua-aprovacao\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/prova-de-titulos-qual-e-o-impacto-da-etapa-na-sua-aprovacao\/\"},\"author\":{\"name\":\"J\u00falia Branco\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/8a4a2ce92e69596f6fc586bac2e00aa6\"},\"headline\":\"Prova de t\u00edtulos: qual \u00e9 o impacto da etapa na sua aprova\u00e7\u00e3o?\",\"datePublished\":\"2020-11-23T21:00:44+00:00\",\"dateModified\":\"2021-01-22T20:05:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/prova-de-titulos-qual-e-o-impacto-da-etapa-na-sua-aprovacao\/\"},\"wordCount\":1447,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/prova-de-titulos-qual-e-o-impacto-da-etapa-na-sua-aprovacao\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/lh3.googleusercontent.com\/cySbCgwzmFxHexFP1f_GybLncyBuR8du24zPbZMqR3QE2ydjK6dWSSAwBFkypRRIHZXfREzSA3OFOjuYdvHR0UqU9HVbBpehyOjVEphzPGnCwxh4uXRToqXyX3CcRVS5-k15omZs\",\"keywords\":[\"p\u00f3s-gradua\u00e7\u00e3o a dist\u00e2ncia\",\"p\u00f3s-gradua\u00e7\u00e3o ead\",\"prova de t\u00edtulos\"],\"articleSection\":[\"Concursos P\u00fablicos\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/prova-de-titulos-qual-e-o-impacto-da-etapa-na-sua-aprovacao\/#respond\"]}],\"copyrightYear\":\"2020\",\"copyrightHolder\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/prova-de-titulos-qual-e-o-impacto-da-etapa-na-sua-aprovacao\/\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/prova-de-titulos-qual-e-o-impacto-da-etapa-na-sua-aprovacao\/\",\"name\":\"Prova de t\u00edtulos: qual \u00e9 o impacto da etapa na sua aprova\u00e7\u00e3o?\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/prova-de-titulos-qual-e-o-impacto-da-etapa-na-sua-aprovacao\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/prova-de-titulos-qual-e-o-impacto-da-etapa-na-sua-aprovacao\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/lh3.googleusercontent.com\/cySbCgwzmFxHexFP1f_GybLncyBuR8du24zPbZMqR3QE2ydjK6dWSSAwBFkypRRIHZXfREzSA3OFOjuYdvHR0UqU9HVbBpehyOjVEphzPGnCwxh4uXRToqXyX3CcRVS5-k15omZs\",\"datePublished\":\"2020-11-23T21:00:44+00:00\",\"dateModified\":\"2021-01-22T20:05:19+00:00\",\"description\":\"Saiba como a prova de t\u00edtulos nos concursos p\u00fablicos pode impactar a sua aprova\u00e7\u00e3o. Entenda como funciona a pontua\u00e7\u00e3o obtida pelos candidatos...\",\"breadcrumb\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/prova-de-titulos-qual-e-o-impacto-da-etapa-na-sua-aprovacao\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/prova-de-titulos-qual-e-o-impacto-da-etapa-na-sua-aprovacao\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/prova-de-titulos-qual-e-o-impacto-da-etapa-na-sua-aprovacao\/#primaryimage\",\"url\":\"https:\/\/lh3.googleusercontent.com\/cySbCgwzmFxHexFP1f_GybLncyBuR8du24zPbZMqR3QE2ydjK6dWSSAwBFkypRRIHZXfREzSA3OFOjuYdvHR0UqU9HVbBpehyOjVEphzPGnCwxh4uXRToqXyX3CcRVS5-k15omZs\",\"contentUrl\":\"https:\/\/lh3.googleusercontent.com\/cySbCgwzmFxHexFP1f_GybLncyBuR8du24zPbZMqR3QE2ydjK6dWSSAwBFkypRRIHZXfREzSA3OFOjuYdvHR0UqU9HVbBpehyOjVEphzPGnCwxh4uXRToqXyX3CcRVS5-k15omZs\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/prova-de-titulos-qual-e-o-impacto-da-etapa-na-sua-aprovacao\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Prova de t\u00edtulos: qual \u00e9 o impacto da etapa na sua aprova\u00e7\u00e3o?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"name\":\"Estrat\u00e9gia Concursos\",\"description\":\"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.\",\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\",\"name\":\"Estrat\u00e9gia Concursos\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"width\":230,\"height\":60,\"caption\":\"Estrat\u00e9gia Concursos\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/EstratConcursos\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/8a4a2ce92e69596f6fc586bac2e00aa6\",\"name\":\"J\u00falia Branco\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/0f766fa82cc670dc5dc1bfb2b089001368538ed907cbd3f55bb04c1f70f134b5?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/0f766fa82cc670dc5dc1bfb2b089001368538ed907cbd3f55bb04c1f70f134b5?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/0f766fa82cc670dc5dc1bfb2b089001368538ed907cbd3f55bb04c1f70f134b5?s=96&d=mm&r=g\",\"caption\":\"J\u00falia Branco\"},\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/juliakbrancogmail-com\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Prova de t\u00edtulos: qual \u00e9 o impacto da etapa na sua aprova\u00e7\u00e3o?","description":"Saiba como a prova de t\u00edtulos nos concursos p\u00fablicos pode impactar a sua aprova\u00e7\u00e3o. Entenda como funciona a pontua\u00e7\u00e3o obtida pelos candidatos...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.estrategiaconcursos.com.br\/blog\/prova-de-titulos-qual-e-o-impacto-da-etapa-na-sua-aprovacao\/","og_locale":"pt_BR","og_type":"article","og_title":"Prova de t\u00edtulos: qual \u00e9 o impacto da etapa na sua aprova\u00e7\u00e3o?","og_description":"Saiba como a prova de t\u00edtulos nos concursos p\u00fablicos pode impactar a sua aprova\u00e7\u00e3o. Entenda como funciona a pontua\u00e7\u00e3o obtida pelos candidatos...","og_url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/prova-de-titulos-qual-e-o-impacto-da-etapa-na-sua-aprovacao\/","og_site_name":"Estrat\u00e9gia Concursos","article_published_time":"2020-11-23T21:00:44+00:00","article_modified_time":"2021-01-22T20:05:19+00:00","og_image":[{"url":"https:\/\/lh3.googleusercontent.com\/cySbCgwzmFxHexFP1f_GybLncyBuR8du24zPbZMqR3QE2ydjK6dWSSAwBFkypRRIHZXfREzSA3OFOjuYdvHR0UqU9HVbBpehyOjVEphzPGnCwxh4uXRToqXyX3CcRVS5-k15omZs","type":"","width":"","height":""}],"author":"J\u00falia Branco","twitter_card":"summary_large_image","twitter_creator":"@EstratConcursos","twitter_site":"@EstratConcursos","twitter_misc":{"Escrito por":"J\u00falia Branco","Est. tempo de leitura":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/prova-de-titulos-qual-e-o-impacto-da-etapa-na-sua-aprovacao\/#article","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/prova-de-titulos-qual-e-o-impacto-da-etapa-na-sua-aprovacao\/"},"author":{"name":"J\u00falia Branco","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/8a4a2ce92e69596f6fc586bac2e00aa6"},"headline":"Prova de t\u00edtulos: qual \u00e9 o impacto da etapa na sua aprova\u00e7\u00e3o?","datePublished":"2020-11-23T21:00:44+00:00","dateModified":"2021-01-22T20:05:19+00:00","mainEntityOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/prova-de-titulos-qual-e-o-impacto-da-etapa-na-sua-aprovacao\/"},"wordCount":1447,"commentCount":0,"publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/prova-de-titulos-qual-e-o-impacto-da-etapa-na-sua-aprovacao\/#primaryimage"},"thumbnailUrl":"https:\/\/lh3.googleusercontent.com\/cySbCgwzmFxHexFP1f_GybLncyBuR8du24zPbZMqR3QE2ydjK6dWSSAwBFkypRRIHZXfREzSA3OFOjuYdvHR0UqU9HVbBpehyOjVEphzPGnCwxh4uXRToqXyX3CcRVS5-k15omZs","keywords":["p\u00f3s-gradua\u00e7\u00e3o a dist\u00e2ncia","p\u00f3s-gradua\u00e7\u00e3o ead","prova de t\u00edtulos"],"articleSection":["Concursos P\u00fablicos"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/prova-de-titulos-qual-e-o-impacto-da-etapa-na-sua-aprovacao\/#respond"]}],"copyrightYear":"2020","copyrightHolder":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/prova-de-titulos-qual-e-o-impacto-da-etapa-na-sua-aprovacao\/","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/prova-de-titulos-qual-e-o-impacto-da-etapa-na-sua-aprovacao\/","name":"Prova de t\u00edtulos: qual \u00e9 o impacto da etapa na sua aprova\u00e7\u00e3o?","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/prova-de-titulos-qual-e-o-impacto-da-etapa-na-sua-aprovacao\/#primaryimage"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/prova-de-titulos-qual-e-o-impacto-da-etapa-na-sua-aprovacao\/#primaryimage"},"thumbnailUrl":"https:\/\/lh3.googleusercontent.com\/cySbCgwzmFxHexFP1f_GybLncyBuR8du24zPbZMqR3QE2ydjK6dWSSAwBFkypRRIHZXfREzSA3OFOjuYdvHR0UqU9HVbBpehyOjVEphzPGnCwxh4uXRToqXyX3CcRVS5-k15omZs","datePublished":"2020-11-23T21:00:44+00:00","dateModified":"2021-01-22T20:05:19+00:00","description":"Saiba como a prova de t\u00edtulos nos concursos p\u00fablicos pode impactar a sua aprova\u00e7\u00e3o. Entenda como funciona a pontua\u00e7\u00e3o obtida pelos candidatos...","breadcrumb":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/prova-de-titulos-qual-e-o-impacto-da-etapa-na-sua-aprovacao\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/prova-de-titulos-qual-e-o-impacto-da-etapa-na-sua-aprovacao\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/prova-de-titulos-qual-e-o-impacto-da-etapa-na-sua-aprovacao\/#primaryimage","url":"https:\/\/lh3.googleusercontent.com\/cySbCgwzmFxHexFP1f_GybLncyBuR8du24zPbZMqR3QE2ydjK6dWSSAwBFkypRRIHZXfREzSA3OFOjuYdvHR0UqU9HVbBpehyOjVEphzPGnCwxh4uXRToqXyX3CcRVS5-k15omZs","contentUrl":"https:\/\/lh3.googleusercontent.com\/cySbCgwzmFxHexFP1f_GybLncyBuR8du24zPbZMqR3QE2ydjK6dWSSAwBFkypRRIHZXfREzSA3OFOjuYdvHR0UqU9HVbBpehyOjVEphzPGnCwxh4uXRToqXyX3CcRVS5-k15omZs"},{"@type":"BreadcrumbList","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/prova-de-titulos-qual-e-o-impacto-da-etapa-na-sua-aprovacao\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.estrategiaconcursos.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Prova de t\u00edtulos: qual \u00e9 o impacto da etapa na sua aprova\u00e7\u00e3o?"}]},{"@type":"WebSite","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","name":"Estrat\u00e9gia Concursos","description":"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.","publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization","name":"Estrat\u00e9gia Concursos","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","width":230,"height":60,"caption":"Estrat\u00e9gia Concursos"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/EstratConcursos"]},{"@type":"Person","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/8a4a2ce92e69596f6fc586bac2e00aa6","name":"J\u00falia Branco","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/0f766fa82cc670dc5dc1bfb2b089001368538ed907cbd3f55bb04c1f70f134b5?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/0f766fa82cc670dc5dc1bfb2b089001368538ed907cbd3f55bb04c1f70f134b5?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0f766fa82cc670dc5dc1bfb2b089001368538ed907cbd3f55bb04c1f70f134b5?s=96&d=mm&r=g","caption":"J\u00falia Branco"},"url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/juliakbrancogmail-com\/"}]}},"_links":{"self":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/615215","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/users\/1432"}],"replies":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/comments?post=615215"}],"version-history":[{"count":3,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/615215\/revisions"}],"predecessor-version":[{"id":656174,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/615215\/revisions\/656174"}],"wp:attachment":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media?parent=615215"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/categories?post=615215"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tags?post=615215"},{"taxonomy":"tax_estado","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tax_estado?post=615215"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}