{"id":597832,"date":"2020-11-04T15:23:00","date_gmt":"2020-11-04T18:23:00","guid":{"rendered":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?p=597832"},"modified":"2020-11-03T03:25:34","modified_gmt":"2020-11-03T06:25:34","slug":"regras-de-competencia-do-cpc","status":"publish","type":"post","link":"https:\/\/www.estrategiaconcursos.com.br\/blog\/regras-de-competencia-do-cpc\/","title":{"rendered":"Regras de Compet\u00eancia do C\u00f3digo de Processo Civil \u2013 Parte I"},"content":{"rendered":"\n<p>Entenda quais s\u00e3o os t\u00f3picos mais importantes no que tange \u00e0s Regras de Compet\u00eancia do Processo Civil e direcione seus estudos, focando nos assuntos que costumam ser cobradas nas provas de concursos.&nbsp;&nbsp;<\/p>\n\n\n\n<p>Esse artigo faz parte da s\u00e9rie de resumos de Direito Processual Civil, em que est\u00e3o sendo apresentados os principais temas do&nbsp;<a href=\"http:\/\/www.planalto.gov.br\/ccivil_03\/_ato2015-2018\/2015\/lei\/l13105.htm\" target=\"_blank\" rel=\"noreferrer noopener\">C\u00f3digo de Processo Civil<\/a>&nbsp;(CPC), dando maior enfoque nos conte\u00fados que aparecem com mais frequ\u00eancia em quest\u00f5es de concurso.&nbsp;<\/p>\n\n\n\n<p>No \u00faltimo artigo tratamos dos&nbsp;<a rel=\"noreferrer noopener\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/limites-da-jurisdicao-nacional\/\" target=\"_blank\">Limites da Jurisdi\u00e7\u00e3o Nacional<\/a>&nbsp;. Hoje vamos adentrar em um assunto que costuma aparecer reiteradamente em provas:&nbsp;Regras de Compet\u00eancia do&nbsp;Processo Civil.&nbsp;<\/p>\n\n\n\n<p>Para explica\u00e7\u00f5es mais detalhadas, com exemplos pr\u00e1ticos e resolu\u00e7\u00e3o passo a passo dos exerc\u00edcios<a href=\"https:\/\/www.estrategiaconcursos.com.br\/pesquisa\/?q=direito+processual+civil\" target=\"_blank\" rel=\"noreferrer noopener\">&nbsp;acesse aqui<\/a>&nbsp;nossos cursos de Direito Processual Civil, elaborados pelos melhores professores da \u00e1rea.&nbsp;<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Regras de Compet\u00eancia do Processo Civil<\/strong>&nbsp;<\/h2>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"602\" height=\"297\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/10\/28102216\/juiz.jpg\" alt=\"Regras de Compet\u00eancia do C\u00f3digo de Processo Civil\" class=\"wp-image-597855\" srcset=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/10\/28102216\/juiz.jpg 602w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/10\/28102216\/juiz-300x148.jpg 300w\" sizes=\"auto, (max-width: 602px) 100vw, 602px\" \/><figcaption>Juiz<\/figcaption><\/figure><\/div>\n\n\n\n<p>As regras de compet\u00eancia interna do Processo Civil encontram-se normatizadas do artigo 42 ao artigo 66 do CPC, dividindo-se em regras gerais, regras de fixa\u00e7\u00e3o da compet\u00eancia, regras de modifica\u00e7\u00e3o de compet\u00eancia e regras de incompet\u00eancia.&nbsp;&nbsp;<\/p>\n\n\n\n<p>Esse \u00e9 um assunto extenso e que costuma aparecer reiteradamente em provas de concurso, portanto, vamos desmistificar as regras de compet\u00eancia dispostas no C\u00f3digo de Processo Civil, de forma a facilitar a compreens\u00e3o da l\u00f3gica do conte\u00fado para otimizar a memoriza\u00e7\u00e3o dos pontos mais importantes da mat\u00e9ria. Hoje vamos come\u00e7ar com as regras gerais e regras de fixa\u00e7\u00e3o de compet\u00eancia.&nbsp;<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Regras Gerais&nbsp;<\/h2>\n\n\n\n<p>Os ju\u00edzes brasileiros possuem jurisdi\u00e7\u00e3o sobre todo o territ\u00f3rio nacional, ou seja, todos os ju\u00edzes t\u00eam o poder de aplicar o Direito no caso concreto. Por\u00e9m, cada juiz tem compet\u00eancia jurisdicional para julgar determinado caso, de acordo com as regras de organiza\u00e7\u00e3o do sistema judici\u00e1rio brasileiro.&nbsp;&nbsp;<\/p>\n\n\n\n<p>As regras de compet\u00eancia, portanto, revelam quem \u00e9 o juiz concretamente competente para julgar determinado processo. Dessa forma, os ju\u00edzes s\u00f3 podem atuar em processos que&nbsp;estejam&nbsp;nos limites de sua compet\u00eancia.&nbsp;&nbsp;<\/p>\n\n\n\n<p>Os seguintes dispositivos legais devem ser considerados para a fixa\u00e7\u00e3o de compet\u00eancia:&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Constitui\u00e7\u00e3o Federal;&nbsp;<\/li><li>Tratados internacionais;&nbsp;<\/li><li>Legisla\u00e7\u00e3o federal;&nbsp;<\/li><li>Legisla\u00e7\u00e3o estadual.&nbsp;<\/li><\/ul>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>Dispositivo Legal:<\/strong>&nbsp;<\/h4>\n\n\n\n<p><em>Art. 44. Obedecidos os&nbsp;<\/em><strong><em>limites estabelecidos pela&nbsp;<\/em><\/strong><a rel=\"noreferrer noopener\" href=\"http:\/\/www.planalto.gov.br\/ccivil_03\/Constituicao\/Constituicao.htm\" target=\"_blank\"><em>Constitui\u00e7\u00e3o Federal&nbsp;<\/em><\/a><em>, a compet\u00eancia \u00e9 determinada pelas normas previstas&nbsp;<\/em><strong><em>neste C\u00f3digo ou em legisla\u00e7\u00e3o especial<\/em><\/strong><em>, pelas&nbsp;<\/em><strong><em>normas de organiza\u00e7\u00e3o judici\u00e1ria<\/em><\/strong><em>&nbsp;e, ainda, no que couber, pelas&nbsp;<\/em><strong><em>constitui\u00e7\u00f5es dos Estados<\/em><\/strong><em>.<\/em>&nbsp;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Ju\u00edzo arbitral<\/strong>&nbsp;<\/h3>\n\n\n\n<p>O Brasil permite o chamado ju\u00edzo arbitral, que \u00e9 uma forma extrajudicial de resolu\u00e7\u00e3o dos conflitos, em que as partes instituem \u00e1rbitro que faz o papel de \u201cjuiz paraestatal\u201d, ouvindo as partes e proferindo uma \u201csenten\u00e7a arbitral\u201d, conforme lei que regulamenta a arbitragem. Quando as partes optam pelo ju\u00edzo arbitral, n\u00e3o se aplicam as regras de compet\u00eancia do Processo Civil.&nbsp;<\/p>\n\n\n\n<p><em>Art. 42. As causas c\u00edveis ser\u00e3o processadas e decididas pelo juiz nos limites de sua compet\u00eancia,&nbsp;<\/em><strong><em>RESSALVADO \u00e0s partes o direito de instituir ju\u00edzo arbitral<\/em><\/strong><em>, na forma da lei.<\/em>&nbsp;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Momento da fixa\u00e7\u00e3o da compet\u00eancia<\/strong>&nbsp;<\/h3>\n\n\n\n<p>A fixa\u00e7\u00e3o da compet\u00eancia especificamente a determinado magistrado se d\u00e1 no momento do&nbsp;<strong>registro da peti\u00e7\u00e3o inicial<\/strong>, quando se trata de vara \u00fanica; ou da&nbsp;<strong>distribui\u00e7\u00e3o da peti\u00e7\u00e3o inicial<\/strong>, quando h\u00e1 v\u00e1rias varas na mesma comarca,&nbsp;realizando-se a distribui\u00e7\u00e3o dos processos por sorteio entre as diversas varas competentes.&nbsp;<\/p>\n\n\n\n<p>Via de regra, ap\u00f3s fixada, ocorre a&nbsp;<strong>perpetua\u00e7\u00e3o da compet\u00eancia<\/strong>, ou seja, independentemente de modifica\u00e7\u00f5es posteriores do estado de fato ou de direito da causa, a compet\u00eancia permanece sendo do mesmo ju\u00edzo.&nbsp;<\/p>\n\n\n\n<p>Essa regra s\u00f3 excepcionada quando h\u00e1 incompet\u00eancia superveniente do ju\u00edzo prevento (primeiro ju\u00edzo). Isso ocorre nos casos de&nbsp;<strong>supress\u00e3o do \u00f3rg\u00e3o judici\u00e1rio<\/strong>, por exemplo com a extin\u00e7\u00e3o da vara, ou nos casos de<strong>&nbsp;altera\u00e7\u00e3o da compet\u00eancia absoluta<\/strong>, por exemplo quando uma mat\u00e9ria que era compet\u00eancia da justi\u00e7a comum passa a ser compet\u00eancia da justi\u00e7a do trabalho por altera\u00e7\u00e3o legal.&nbsp;<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>Dispositivo Legal:<\/strong>&nbsp;<\/h4>\n\n\n\n<p><em>Art. 43.&nbsp;<\/em><strong><em>Determina-se a compet\u00eancia no momento do registro ou da distribui\u00e7\u00e3o da peti\u00e7\u00e3o inicial<\/em><\/strong><em>, sendo<strong> irrelevantes as modifica\u00e7\u00f5es do estado de fato ou de direito<\/strong> ocorridas posteriormente,<strong> SALVO quando suprimirem \u00f3rg\u00e3o judici\u00e1rio<\/strong> ou <strong>alterarem a compet\u00eancia absoluta<\/strong>.<\/em>&nbsp;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Compet\u00eancia no CPC<\/strong>&nbsp;<\/h3>\n\n\n\n<p>Existem diversos crit\u00e9rios para a fixa\u00e7\u00e3o de compet\u00eancia que visam facilitar a identifica\u00e7\u00e3o do ju\u00edzo competente para julgamento de determinada a\u00e7\u00e3o em meio ao emaranhado de regras e \u00f3rg\u00e3os jurisdicionais existentes no pa\u00eds.&nbsp;&nbsp;<\/p>\n\n\n\n<p>Vamos esmiu\u00e7ar as regras de compet\u00eancia fixadas especificamente no CPC, relativas \u00e0s causas c\u00edveis que tramitam perante a justi\u00e7a comum. Cabe salientar, entretanto, que o CPC \u00e9 aplicado de forma subsidi\u00e1ria \u00e0s causas que tramitam perante a justi\u00e7a especializada (Justi\u00e7a Eleitoral, Justi\u00e7a do Trabalho e Justi\u00e7a Militar).&nbsp;<\/p>\n\n\n\n<p>A justi\u00e7a comum se divide em Justi\u00e7a Federal e Justi\u00e7a Estadual. Se o processo n\u00e3o \u00e9 de compet\u00eancia de nenhuma justi\u00e7a especializada, ele \u00e9 de compet\u00eancia da justi\u00e7a comum. Mas como saber diferenciar a compet\u00eancia federal e a compet\u00eancia estadual?&nbsp;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Justi\u00e7a Federal<\/strong>&nbsp;<\/h3>\n\n\n\n<p>A compet\u00eancia federal \u00e9 determinada por dois crit\u00e9rios: partes ou causa de pedir.&nbsp;No que diz respeito \u00e0 causa de pedir, as regras de defini\u00e7\u00e3o de compet\u00eancia federal est\u00e3o dispostas na Constitui\u00e7\u00e3o Federal, em seu artigo 109, n\u00e3o nos interessando no momento, j\u00e1 que nosso foco s\u00e3o as regras do CPC.&nbsp;<\/p>\n\n\n\n<p>No que diz respeito \u00e0s partes, a Justi\u00e7a Federal julga as a\u00e7\u00f5es que tenham como autores, r\u00e9us ou terceiros interessados os seguintes Entes e Entidades:&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>A&nbsp;Uni\u00e3o;&nbsp;<\/li><li>Empresas p\u00fablicas da Uni\u00e3o&nbsp;(sociedades de economia mista federal n\u00e3o est\u00e3o inclu\u00eddas);&nbsp;<\/li><li>Entidades aut\u00e1rquicas federais;&nbsp;<\/li><li>Funda\u00e7\u00f5es federais;&nbsp;ou&nbsp;&nbsp;<\/li><li>Conselho de fiscaliza\u00e7\u00e3o de atividade profissional.&nbsp;&nbsp;<\/li><\/ul>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>Regra:<\/strong>&nbsp;<\/h4>\n\n\n\n<p>Se alguma dessas Entidades pede para intervir em uma causa que tramita na Justi\u00e7a Estadual, em regra, o juiz estadual deve remeter os autos ao ju\u00edzo federal competente. Se o juiz federal n\u00e3o admitir a interven\u00e7\u00e3o da Entidade Federal, ele deve exclu\u00ed-la da a\u00e7\u00e3o e remeter os autos de volta \u00e0 Justi\u00e7a Estadual.&nbsp;<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>Exce\u00e7\u00f5es:<\/strong>&nbsp;<\/h4>\n\n\n\n<p>A)&nbsp;Excepcionalmente, havendo a interven\u00e7\u00e3o de Entidade Federal, se houver na causa pedido cuja aprecia\u00e7\u00e3o seja de compet\u00eancia do ju\u00edzo estadual, n\u00e3o haver\u00e1 remessa ao ju\u00edzo federal, mas a simples exclus\u00e3o do pedido que interesse \u00e0 Entidade Federal.&nbsp;<\/p>\n\n\n\n<p>B)&nbsp;H\u00e1 ainda no CPC outras&nbsp;exce\u00e7\u00f5es, em que, mesmo havendo uma Entidade Federal como parte, o processo deve correr na Justi\u00e7a Estadual ou na Justi\u00e7a Especializada. As exce\u00e7\u00f5es referem-se a causas relativas \u00e0:&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Fal\u00eancia;&nbsp;<\/li><li>Recupera\u00e7\u00e3o judicial;&nbsp;<\/li><li>Insolv\u00eancia civil;&nbsp;&nbsp;<\/li><li>Acidente de trabalho;&nbsp;<\/li><li>A\u00e7\u00e3o sujeita \u00e0 Justi\u00e7a Eleitoral;&nbsp;<\/li><li>A\u00e7\u00e3o sujeita \u00e0 Justi\u00e7a do Trabalho.&nbsp;<\/li><\/ul>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>Dispositivo Legal:<\/strong>&nbsp;<\/h4>\n\n\n\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\">\n<p><em>Art. 45. Tramitando o processo perante outro ju\u00edzo,&nbsp;<\/em><strong><em>os autos ser\u00e3o remetidos ao ju\u00edzo federal competente se nele intervier a Uni\u00e3o, suas empresas p\u00fablicas, entidades aut\u00e1rquicas e funda\u00e7\u00f5es, ou conselho de fiscaliza\u00e7\u00e3o de atividade profissional<\/em><\/strong><em>, na qualidade de parte ou de terceiro interveniente,&nbsp;<\/em><strong><em>EXCETO&nbsp;<\/em><\/strong><em>as a\u00e7\u00f5es:<\/em>&nbsp;<\/p>\n\n\n\n<p><em>I &#8211;&nbsp;<\/em><em>de<\/em><strong><em>&nbsp;recupera\u00e7\u00e3o judicial, fal\u00eancia, insolv\u00eancia civil e acidente de trabalho<\/em><\/strong><em>;<\/em>&nbsp;<\/p>\n\n\n\n<p><em>II &#8211;&nbsp;<\/em><em>sujeitas<\/em><em>&nbsp;\u00e0&nbsp;<\/em><strong><em>justi\u00e7a eleitoral e \u00e0 justi\u00e7a do trabalho.<\/em><\/strong>&nbsp;<\/p>\n\n\n\n<p><em>\u00a7 1\u00ba Os&nbsp;<\/em><strong><em>autos N\u00c3O ser\u00e3o remetidos&nbsp;<\/em><\/strong><em>se houver&nbsp;<\/em><strong><em>pedido cuja aprecia\u00e7\u00e3o seja de compet\u00eancia do ju\u00edzo perante o qual foi proposta a a\u00e7\u00e3o<\/em><\/strong><em>.<\/em>&nbsp;<\/p>\n\n\n\n<p><em>\u00a7 2\u00ba Na hip\u00f3tese do \u00a7 1\u00ba,&nbsp;<\/em><strong><em>o juiz, ao n\u00e3o admitir a cumula\u00e7\u00e3o<\/em><\/strong><em>&nbsp;de pedidos em raz\u00e3o da incompet\u00eancia para apreciar qualquer deles,&nbsp;<\/em><strong><em>n\u00e3o examinar\u00e1 o m\u00e9rito daquele em que exista interesse da Uni\u00e3o, de suas entidades aut\u00e1rquicas ou de suas empresas p\u00fablicas.<\/em><\/strong>&nbsp;<\/p>\n\n\n\n<p><em>\u00a7 3\u00ba O ju\u00edzo federal restituir\u00e1 os autos ao ju\u00edzo estadual sem suscitar conflito se o ente federal cuja presen\u00e7a ensejou a remessa<\/em><strong><em>&nbsp;for exclu\u00eddo do processo.<\/em><\/strong>&nbsp;<\/p>\n<\/div><\/div>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Justi\u00e7a Estadual<\/strong>&nbsp;<\/h3>\n\n\n\n<p>A compet\u00eancia estadual \u00e9 determinada por exclus\u00e3o, ou seja, n\u00e3o sendo compet\u00eancia das justi\u00e7as especiais ou da Justi\u00e7a Federal, a a\u00e7\u00e3o ser\u00e1 atribu\u00edda \u00e0 Justi\u00e7a Estadual.&nbsp;<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Crit\u00e9rios de fixa\u00e7\u00e3o de compet\u00eancia<\/strong>&nbsp;<\/h2>\n\n\n\n<p>As regras de fixa\u00e7\u00e3o de compet\u00eancia presentes no CPC dizem respeito ao local (foro) em que a a\u00e7\u00e3o deve ser proposta, que pode variar em raz\u00e3o da mat\u00e9ria ou das partes processuais. <\/p>\n\n\n\n<p>Essas regras ser\u00e3o apresentadas a seguir:<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>1) Direito pessoal ou direito real sobre bens m\u00f3veis<\/strong>&nbsp;<\/h3>\n\n\n\n<p>As&nbsp;a\u00e7\u00f5es fundadas em direito pessoal&nbsp;decorrem de um v\u00ednculo obrigacional entre duas ou mais pessoas, a exemplo de uma rela\u00e7\u00e3o contratual. J\u00e1 nas&nbsp;a\u00e7\u00f5es fundadas em direito real sobre bens m\u00f3veis,&nbsp;discute-se o direito de posse, propriedades, entre outros direitos reais de bem m\u00f3vel, a exemplo da disputa judicial pela propriedade de um determinado carro.&nbsp;&nbsp;<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>Regra:&nbsp;<\/strong>&nbsp;<\/h4>\n\n\n\n<p>O ajuizamento da demanda deve ser feito no foro do domic\u00edlio do r\u00e9u.&nbsp;<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>Exce\u00e7\u00f5es:&nbsp;<\/strong>&nbsp;<\/h4>\n\n\n\n<p>A) Se o r\u00e9u tem dois ou mais domic\u00edlios, o autor poder\u00e1 escolher&nbsp;um&nbsp;dentre os v\u00e1rios domic\u00edlios do r\u00e9u.&nbsp;&nbsp;<\/p>\n\n\n\n<p>B) Se incerto ou desconhecido o domic\u00edlio do r\u00e9u, o autor poder\u00e1 ajuizar a a\u00e7\u00e3o:&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>No local em que o r\u00e9u for encontrado; ou&nbsp;&nbsp;<\/li><\/ul>\n\n\n\n<ul class=\"wp-block-list\"><li>No foro de seu pr\u00f3prio domic\u00edlio (do autor).&nbsp;&nbsp;<\/li><\/ul>\n\n\n\n<p>C) Se o r\u00e9u n\u00e3o tiver domic\u00edlio no Brasil, aju\u00edza-se a a\u00e7\u00e3o no local do domic\u00edlio do pr\u00f3prio autor.&nbsp;&nbsp;<\/p>\n\n\n\n<p>D) Se nem r\u00e9u nem autor tiverem domic\u00edlio no Brasil, a a\u00e7\u00e3o pode ser ajuizada em qualquer foro.&nbsp;<\/p>\n\n\n\n<p>E) Se existirem dois r\u00e9us (litiscons\u00f3rcio passivo):&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Caso tenham o mesmo domic\u00edlio, a a\u00e7\u00e3o ser\u00e1 ajuizada neste.&nbsp;&nbsp;<\/li><\/ul>\n\n\n\n<ul class=\"wp-block-list\"><li>Se tiverem domic\u00edlio em locais distintos o autor pode optar por qualquer dos foros de domic\u00edlio dos r\u00e9us.&nbsp;<\/li><\/ul>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>Dispositivo Legal:<\/strong>&nbsp;<\/h4>\n\n\n\n<p><em>Art. 46. A&nbsp;<\/em><strong><em>a\u00e7\u00e3o fundada em direito pessoal<\/em><\/strong><em>&nbsp;ou em&nbsp;<\/em><strong><em>direito real sobre bens m\u00f3veis<\/em><\/strong><em>&nbsp;ser\u00e1 proposta, em regra, no foro de&nbsp;<\/em><strong><em>domic\u00edlio do r\u00e9u.<\/em><\/strong>&nbsp;<\/p>\n\n\n\n<p><em>\u00a7 1\u00ba Tendo&nbsp;<\/em><strong><em>mais de um domic\u00edlio<\/em><\/strong><em>, o r\u00e9u ser\u00e1 demandado no foro de&nbsp;<\/em><strong><em>qualquer deles<\/em><\/strong><em>.<\/em>&nbsp;<\/p>\n\n\n\n<p><em>\u00a7 2\u00ba Sendo&nbsp;<\/em><strong><em>incerto ou desconhecido o domic\u00edlio&nbsp;<\/em><\/strong><em>do r\u00e9u, ele poder\u00e1 ser demandado&nbsp;<\/em><strong><em>onde for encontrado<\/em><\/strong><em>&nbsp;ou no foro de&nbsp;<\/em><strong><em>domic\u00edlio do autor<\/em><\/strong><em>.<\/em>&nbsp;<\/p>\n\n\n\n<p><em>\u00a7 3\u00ba Quando o r\u00e9u&nbsp;<\/em><strong><em>n\u00e3o tiver domic\u00edlio ou resid\u00eancia no Brasil<\/em><\/strong><em>, a a\u00e7\u00e3o ser\u00e1 proposta no foro de&nbsp;<\/em><strong><em>domic\u00edlio do autor<\/em><\/strong><em>, e, se este&nbsp;<\/em><strong><em>tamb\u00e9m residir fora do Brasil,<\/em><\/strong><em>&nbsp;a a\u00e7\u00e3o ser\u00e1 proposta em&nbsp;<\/em><strong><em>qualquer foro.<\/em><\/strong>&nbsp;<\/p>\n\n\n\n<p><em>\u00a7 4\u00ba Havendo&nbsp;<\/em><strong><em>2 (dois) ou mais r\u00e9us com diferentes domic\u00edlios<\/em><\/strong><em>, ser\u00e3o demandados no&nbsp;<\/em><strong><em>foro de qualquer deles<\/em><\/strong><em>, \u00e0 escolha do autor.<\/em>&nbsp;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>2) Direito real sobre im\u00f3veis<\/strong>&nbsp;<\/h3>\n\n\n\n<p>As&nbsp;a\u00e7\u00f5es fundadas em direito real sobre bens im\u00f3veis,<strong>&nbsp;<\/strong>envolvem direitos reais e a\u00e7\u00f5es possess\u00f3rias imobili\u00e1rias, a exemplo da a\u00e7\u00e3o da usucapi\u00e3o.&nbsp;<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>Regra:<\/strong>&nbsp;<\/h4>\n\n\n\n<p>Como a discuss\u00e3o envolve im\u00f3veis, a a\u00e7\u00e3o deve ser&nbsp;ajuizada&nbsp;no local onde estiver situado o im\u00f3vel, tamb\u00e9m chamado de foro de situa\u00e7\u00e3o da coisa <em>(forum&nbsp;rei&nbsp;sitae).&nbsp;<\/em><\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>Exce\u00e7\u00e3o:<\/strong>&nbsp;<\/h4>\n\n\n\n<p>Se a a\u00e7\u00e3o n\u00e3o tiver como objeto o direito de propriedade, vizinhan\u00e7a, servid\u00e3o, divis\u00e3o e demarca\u00e7\u00e3o de terras, nuncia\u00e7\u00e3o de obra nova&nbsp;e n\u00e3o envolver a\u00e7\u00f5es possess\u00f3rias,&nbsp;as partes podem optar por ajuizar a a\u00e7\u00e3o:&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>No domic\u00edlio do r\u00e9u; ou&nbsp;<\/li><li>No foro de elei\u00e7\u00e3o (qualquer outro local&nbsp;determinado&nbsp;em contrato).&nbsp;<\/li><\/ul>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>Dispositivo Legal:<\/strong>&nbsp;<\/h4>\n\n\n\n<p><em>Art. 47. Para as a\u00e7\u00f5es fundadas em<\/em><strong><em>&nbsp;direito real sobre im\u00f3veis&nbsp;<\/em><\/strong><em>\u00e9 competente o foro de&nbsp;<\/em><strong><em>situa\u00e7\u00e3o da coisa.&nbsp;<\/em><\/strong>&nbsp;<\/p>\n\n\n\n<p><em>\u00a7 1\u00ba O autor pode optar pelo&nbsp;<\/em><strong><em>foro de domic\u00edlio do r\u00e9u<\/em><\/strong><em>&nbsp;ou pelo&nbsp;<\/em><strong><em>foro de elei\u00e7\u00e3o&nbsp;<\/em><\/strong><em>se o<\/em><strong><em>&nbsp;<\/em><\/strong><strong><em>lit\u00edgio N\u00c3O recair sobre direito de propriedade, vizinhan\u00e7a, servid\u00e3o, divis\u00e3o e demarca\u00e7\u00e3o de terras e de nuncia\u00e7\u00e3o de obra nova.<\/em><\/strong><em>&nbsp;<\/em>&nbsp;<\/p>\n\n\n\n<p><em>\u00a7 2\u00ba A&nbsp;<\/em><strong><em>a\u00e7\u00e3o possess\u00f3ria&nbsp;<\/em><\/strong><em>imobili\u00e1ria ser\u00e1 proposta no&nbsp;<\/em><strong><em>foro de situa\u00e7\u00e3o da coisa<\/em><\/strong><em>, cujo ju\u00edzo tem compet\u00eancia absoluta.<\/em>&nbsp;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>3) Cumprimento de obriga\u00e7\u00e3o<\/strong>&nbsp;<\/h3>\n\n\n\n<p>Diz respeito \u00e0 a\u00e7\u00e3o que visa o cumprimento de obriga\u00e7\u00f5es contratuais, como um contrato de presta\u00e7\u00e3o de servi\u00e7os.&nbsp;<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>Regra:<\/strong>&nbsp;<\/h4>\n\n\n\n<p>A a\u00e7\u00e3o deve ser ajuizada no local onde a obriga\u00e7\u00e3o deva ser satisfeita.&nbsp;<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>Dispositivo Legal:<\/strong>&nbsp;<\/h4>\n\n\n\n<p><em>Art. 53. \u00c9 competente o foro:<\/em>&nbsp;<\/p>\n\n\n\n<p><em>III &#8211; do lugar:<\/em>&nbsp;<\/p>\n\n\n\n<p><em>d) onde a&nbsp;<\/em><strong><em>obriga\u00e7\u00e3o deve ser satisfeita<\/em><\/strong><em>, para a&nbsp;<\/em><strong><em>a\u00e7\u00e3o em que se lhe exigir o cumprimento;<\/em><\/strong>&nbsp;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>4) Repara\u00e7\u00e3o de dano<\/strong>&nbsp;<\/h3>\n\n\n\n<p>Diz respeito \u00e0s demandas de repara\u00e7\u00e3o de dano extracontratual, quando h\u00e1, por exemplo, um il\u00edcito civil.&nbsp;<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>Regra:<\/strong>&nbsp;<\/h4>\n\n\n\n<p>A a\u00e7\u00e3o deve ser ajuizada no local do ato ou fato.&nbsp;<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>Dispositivo Legal:<\/strong>&nbsp;<\/h4>\n\n\n\n<p><em>Art. 53. \u00c9 competente o foro:<\/em>&nbsp;<\/p>\n\n\n\n<p><em>IV &#8211;&nbsp;<\/em><strong><em>do<\/em><\/strong><strong><em>&nbsp;lugar do ato ou fato<\/em><\/strong><em>&nbsp;para a a\u00e7\u00e3o:<\/em>&nbsp;<\/p>\n\n\n\n<p><em>a) de&nbsp;<\/em><strong><em>repara\u00e7\u00e3o de dano<\/em><\/strong><em>;<\/em>&nbsp;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>5) Delito ou acidente de ve\u00edculo<\/strong>&nbsp;<\/h3>\n\n\n\n<p>Diz respeito aos casos de a\u00e7\u00e3o de responsabilidade civil por delito civil ou penal ou acidente de ve\u00edculo \u2013 motorizado ou n\u00e3o&nbsp;\u2013,&nbsp;terrestre, a\u00e9reo, mar\u00edtimo, ferrovi\u00e1rio ou fluvial.&nbsp;<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>Regra:<\/strong>&nbsp;<\/h4>\n\n\n\n<p>A a\u00e7\u00e3o pode ser ajuizada:&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>No domic\u00edlio do autor;&nbsp;<\/li><\/ul>\n\n\n\n<ul class=\"wp-block-list\"><li>No local do ato ou fato.&nbsp;<\/li><\/ul>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>Dispositivo Legal:<\/strong>&nbsp;<\/h4>\n\n\n\n<p><em>Art. 53. \u00c9 competente o foro:<\/em>&nbsp;<\/p>\n\n\n\n<p><em>V &#8211;&nbsp;<\/em><em>de<\/em><em>&nbsp;<\/em><strong><em>domic\u00edlio do autor ou do local do fato<\/em><\/strong><em>, para a&nbsp;<\/em><strong><em>a\u00e7\u00e3o de repara\u00e7\u00e3o de dano sofrido em raz\u00e3o de delito ou acidente de ve\u00edculos<\/em><\/strong><em>, inclusive aeronaves.<\/em>&nbsp;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>6) Sucess\u00e3o causa mortis<\/strong>\u00a0&#8211; Regras de Compet\u00eancia<\/h3>\n\n\n\n<p>Quando uma pessoa morre e deixa bens m\u00f3veis e\/ou im\u00f3veis, os herdeiros entram com a a\u00e7\u00e3o de sucess\u00e3o causa mortis para fazer a divis\u00e3o desses bens. As regras a seguir valem para o invent\u00e1rio, a partilha, a arrecada\u00e7\u00e3o, o cumprimento de disposi\u00e7\u00f5es de \u00faltima vontade, a impugna\u00e7\u00e3o ou anula\u00e7\u00e3o de partilha extrajudicial e para todas as demais a\u00e7\u00f5es em que o esp\u00f3lio for r\u00e9u.&nbsp;<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>Regra:<\/strong>&nbsp;<\/h4>\n\n\n\n<p>A\u00e7\u00e3o ser\u00e1 ajuizada no \u00faltimo domic\u00edlio do autor da heran\u00e7a (falecido).<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Exce\u00e7\u00f5es:<\/h4>\n\n\n\n<p>A) Se falecido n\u00e3o tinha domic\u00edlio certo, a a\u00e7\u00e3o ser\u00e1 o local da situa\u00e7\u00e3o dos bens im\u00f3veis.&nbsp;&nbsp;<\/p>\n\n\n\n<p>B) Caso o falecido sem domic\u00edlio tenha bens im\u00f3veis em variadas comarcas, o autor poder\u00e1 ajuizar a a\u00e7\u00e3o em qualquer desses foros;&nbsp;&nbsp;<\/p>\n\n\n\n<p>C) Se o falecido n\u00e3o tiver domic\u00edlio nem deixar bens im\u00f3veis, a a\u00e7\u00e3o poder\u00e1 ser ajuizada em qualquer local em que haja bens m\u00f3veis.&nbsp;<\/p>\n\n\n\n<p><strong>Obs.:&nbsp;<\/strong>O local do \u00f3bito n\u00e3o tem qualquer relev\u00e2ncia para defini\u00e7\u00e3o de onde ser\u00e1 ajuizada a\u00e7\u00e3o sucess\u00e3o causa mortis, de forma que, mesmo que esta tenha ocorrido no estrangeiro, as regras acima devem ser aplicadas.&nbsp;<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>Dispositivo Legal:<\/strong>&nbsp;<\/h4>\n\n\n\n<p><em>Art. 48. O&nbsp;<\/em><strong><em>foro de domic\u00edlio do autor da heran\u00e7a, no Brasil, \u00e9 o competente<\/em><\/strong><em>&nbsp;para o invent\u00e1rio, a partilha, a arrecada\u00e7\u00e3o, o cumprimento de disposi\u00e7\u00f5es de \u00faltima vontade, a impugna\u00e7\u00e3o ou anula\u00e7\u00e3o de partilha extrajudicial e para todas as a\u00e7\u00f5es em que o esp\u00f3lio for r\u00e9u, <\/em><strong><em>ainda que o \u00f3bito tenha ocorrido no estrangeiro.&nbsp;<\/em>&nbsp;<\/strong><\/p>\n\n\n\n<p><em>Par\u00e1grafo \u00fanico. Se o&nbsp;<\/em><strong><em>autor da heran\u00e7a n\u00e3o possu\u00eda domic\u00edlio certo<\/em><\/strong><em>, \u00e9 competente:<\/em>&nbsp;<\/p>\n\n\n\n<p><em>I &#8211;&nbsp;<\/em><em>o<\/em><em>&nbsp;foro de&nbsp;<\/em><strong><em>situa\u00e7\u00e3o dos bens im\u00f3veis;&nbsp;<\/em><\/strong>&nbsp;<\/p>\n\n\n\n<p><em>II &#8211; havendo bens<\/em><strong><em>&nbsp;im\u00f3veis em foros diferentes, qualquer destes;&nbsp;<\/em><\/strong>&nbsp;<\/p>\n\n\n\n<p><em>III &#8211;&nbsp;<\/em><strong><em>n<\/em><\/strong><strong><em>\u00e3<\/em><\/strong><strong><em>o havendo bens im\u00f3veis, o foro do local de qualquer dos bens&nbsp;<\/em><\/strong><em>do esp\u00f3lio.<\/em>&nbsp;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>7) Aus\u00eancia<\/strong>&nbsp;<\/h3>\n\n\n\n<p>A aus\u00eancia \u00e9 um instituto do Direito Civil aplicada aos casos em que a pessoa desaparece sem deixar um representante. Como n\u00e3o h\u00e1 certeza sobre o seu falecimento, as regras da aus\u00eancia s\u00e3o diferentes da sucess\u00e3o causa mortis.&nbsp;&nbsp;<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>Regra:<\/strong>&nbsp;<\/h4>\n\n\n\n<p>Dada a possibilidade de decreta\u00e7\u00e3o de morte presumida, a a\u00e7\u00e3o&nbsp;referente \u00e0 arrecada\u00e7\u00e3o, ao invent\u00e1rio, \u00e0 partilha e ao cumprimento de disposi\u00e7\u00f5es testament\u00e1rias&nbsp;dever\u00e1 ser proposta perante o foro do \u00faltimo domic\u00edlio do ausente.&nbsp;<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>Dispositivo Legal:<\/strong>&nbsp;<\/h4>\n\n\n\n<p><em>Art. 49. A a\u00e7\u00e3o em que o&nbsp;<\/em><strong><em>ausente for r\u00e9u<\/em><\/strong><em>&nbsp;ser\u00e1 proposta no&nbsp;<\/em><strong><em>foro de seu \u00faltimo domic\u00edlio<\/em><\/strong><em>, tamb\u00e9m competente para a arrecada\u00e7\u00e3o, o invent\u00e1rio, a partilha e o cumprimento de disposi\u00e7\u00f5es testament\u00e1rias.<\/em>&nbsp;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>8) R\u00e9u incapaz<\/strong>\u00a0&#8211; Regras de Compet\u00eancia<\/h3>\n\n\n\n<p>Essa regra refere-se \u00e0 situa\u00e7\u00e3o em que uma a\u00e7\u00e3o \u00e9 ajuizada contra r\u00e9u incapaz, a exemplo de quando uma crian\u00e7a que quebra vidra\u00e7a do vizinho com uma bola de futebol e se nega a reparar o dano.&nbsp;<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>Regra:<\/strong>&nbsp;<\/h4>\n\n\n\n<p>A a\u00e7\u00e3o ser\u00e1 ajuizada no foro de domic\u00edlio do representante ou do assistente do incapaz que, como regra, ser\u00e3o seus pais.&nbsp;<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>Dispositivo Legal:<\/strong>&nbsp;<\/h4>\n\n\n\n<p><em>Art. 50. A a\u00e7\u00e3o em que o&nbsp;<\/em><strong><em>incapaz for r\u00e9u&nbsp;<\/em><\/strong><em>ser\u00e1 proposta no foro de&nbsp;<\/em><strong><em>domic\u00edlio de seu representante ou assistente.<\/em><\/strong>&nbsp;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>9) Poder P\u00fablico&nbsp;<\/strong>&nbsp;<\/h3>\n\n\n\n<p>S\u00e3o a\u00e7\u00f5es que envolvem a Fazenda P\u00fablica, tendo como uma das partes a Uni\u00e3o, os Estados, os Munic\u00edpios, o Distrito Federal ou as entidades da administra\u00e7\u00e3o p\u00fablica indireta, como autarquias, funda\u00e7\u00f5es p\u00fablicas, empresas p\u00fablicas e sociedades de economia mista.&nbsp;<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>Regra:<\/strong>&nbsp;<\/h4>\n\n\n\n<p>A) Nas a\u00e7\u00f5es ajuizadas pela Uni\u00e3o e suas Entidades (autores), o foro competente ser\u00e1 o domic\u00edlio do r\u00e9u;&nbsp;<\/p>\n\n\n\n<p>B) Nas a\u00e7\u00f5es ajuizadas contra a Uni\u00e3o e suas Entidades (r\u00e9us), o jurisdicionado pode escolher entre:&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>O foro do seu domic\u00edlio;&nbsp;&nbsp;<\/li><li>O local do ato ou fato;&nbsp;&nbsp;<\/li><li>O foro da situa\u00e7\u00e3o da coisa;&nbsp;&nbsp;<\/li><li>O Distrito Federal.&nbsp;<\/li><\/ul>\n\n\n\n<p>C)&nbsp;Nas a\u00e7\u00f5es ajuizadas pelos Estados ou Distrito Federal e suas Entidades (autores), \u00e9 competente o foro do domic\u00edlio do r\u00e9u;&nbsp;<\/p>\n\n\n\n<p>D) Nas a\u00e7\u00f5es ajuizadas contra Estados ou Distrito Federal e suas Entidades (r\u00e9us), o jurisdicionado pode escolher ajuizar a a\u00e7\u00e3o:&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>No foro do seu domic\u00edlio;&nbsp;&nbsp;<\/li><li>No local do ato ou fato;&nbsp;&nbsp;<\/li><li>No foro da situa\u00e7\u00e3o da coisa;&nbsp;&nbsp;<\/li><li>Na capital do respectivo ente federado.&nbsp;<\/li><\/ul>\n\n\n\n<p><strong>Obs.:<\/strong>&nbsp;Caso se trate de a\u00e7\u00e3o contra a Fazenda P\u00fablica Municipal, pelo fato de n\u00e3o existir regra espec\u00edfica, aplicam-se as regras gerais do CPC.&nbsp;<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>Dispositivo Legal:<\/strong>&nbsp;<\/h4>\n\n\n\n<p><em>Art. 51. \u00c9 competente o&nbsp;<\/em><strong><em>foro de domic\u00edlio do r\u00e9u<\/em><\/strong><em>&nbsp;para as causas em que seja&nbsp;<\/em><strong><em>autora a Uni\u00e3o<\/em><\/strong><em>.&nbsp;<\/em>&nbsp;<\/p>\n\n\n\n<p><em>Par\u00e1grafo \u00fanico. Se a<\/em><strong><em>&nbsp;Uni\u00e3o for a demandada,<\/em><\/strong><em>&nbsp;a a\u00e7\u00e3o poder\u00e1 ser proposta no foro de&nbsp;<\/em><strong><em>domic\u00edlio do autor<\/em><\/strong><em>, no de<\/em><strong><em>&nbsp;ocorr\u00eancia do ato ou fato&nbsp;<\/em><\/strong><em>que originou a demanda, no de s<\/em><strong><em>itua\u00e7\u00e3o da coisa&nbsp;<\/em><\/strong><em>ou no&nbsp;<\/em><strong><em>Distrito Federal.<\/em><\/strong>&nbsp;<\/p>\n\n\n\n<p><em>Art. 52. \u00c9 competente o foro de&nbsp;<\/em><strong><em>domic\u00edlio do r\u00e9u<\/em><\/strong><em>&nbsp;para as causas em que seja&nbsp;<\/em><strong><em>autor Estado<\/em><\/strong><strong><em>&nbsp;ou o Distrito Federal.<\/em><\/strong><em>&nbsp;<\/em>&nbsp;<\/p>\n\n\n\n<p><em>Par\u00e1grafo \u00fanico. Se E<\/em><strong><em>stado ou o Distrito Federal for o demandado<\/em><\/strong><em>, a a\u00e7\u00e3o poder\u00e1 ser proposta no foro de&nbsp;<\/em><strong><em>domic\u00edlio do autor,<\/em><\/strong><em>&nbsp;no de&nbsp;<\/em><strong><em>ocorr\u00eancia do ato ou fato<\/em><\/strong><em>&nbsp;que originou a demanda, no de <strong>s<\/strong><\/em><strong><em>itua\u00e7\u00e3o da coisa&nbsp;<\/em><\/strong><em>ou na&nbsp;<\/em><strong><em>capital do respectivo ente&nbsp;<\/em><\/strong><em>federado.<\/em>&nbsp;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>10) Repara\u00e7\u00e3o de dano praticado por cart\u00f3rio<\/strong>\u00a0 &#8211; Regras de Compet\u00eancia<\/h3>\n\n\n\n<p>Trata-se de a\u00e7\u00e3o de repara\u00e7\u00e3o de dano por ato decorrente do of\u00edcio de serventias notariais ou de registro.&nbsp;<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>Regra:<\/strong>&nbsp;<\/h4>\n\n\n\n<p>A demanda dever\u00e1 ser proposta no local da sede da serventia notarial ou de registro.&nbsp;<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>Dispositivo Legal:<\/strong>&nbsp;<\/h4>\n\n\n\n<p><em>Art. 53. \u00c9 competente o foro:&nbsp;<\/em>&nbsp;<\/p>\n\n\n\n<p><em>III &#8211; do lugar:<\/em>&nbsp;<\/p>\n\n\n\n<p><em>f) da&nbsp;<\/em><strong><em>sede da serventia notarial ou de registro<\/em><\/strong><em>, para a a\u00e7\u00e3o de&nbsp;<\/em><strong><em>repara\u00e7\u00e3o de dano por ato praticado em raz\u00e3o do of\u00edcio;<\/em><\/strong>&nbsp;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>11) Casamento e <\/strong>U<strong>ni\u00e3o Est\u00e1vel<\/strong>&nbsp;<\/h3>\n\n\n\n<p>S\u00e3o a\u00e7\u00f5es que envolvam div\u00f3rcio, separa\u00e7\u00e3o, anula\u00e7\u00e3o de casamento e reconhecimento ou dissolu\u00e7\u00e3o de uni\u00e3o est\u00e1vel.&nbsp;<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>Regras:<\/strong>&nbsp;<\/h4>\n\n\n\n<p>A) Se o casal tem filho incapaz, a a\u00e7\u00e3o deve ser ajuizada no domic\u00edlio do guardi\u00e3o de filho incapaz, n\u00e3o importando se este \u00e9 autor ou r\u00e9u da a\u00e7\u00e3o;&nbsp;<\/p>\n\n\n\n<p>B) Quando a parte for v\u00edtima de viol\u00eancia dom\u00e9stica e familiar (nos termos da Lei Maria da Penha) a\u00e7\u00e3o dever\u00e1 ser ajuizada no domic\u00edlio da v\u00edtima;<\/p>\n\n\n\n<p>C) Se o casal n\u00e3o tem filho incapaz e n\u00e3o se trata de v\u00edtima de viol\u00eancia dom\u00e9stica, a a\u00e7\u00e3o deve ser ajuizada \u00faltimo domic\u00edlio do casal;&nbsp;<\/p>\n\n\n\n<p>D) Se nenhuma das partes residir no antigo domic\u00edlio do casal, a a\u00e7\u00e3o deve ser ajuizada no domic\u00edlio do r\u00e9u.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>Dispositivo Legal:<\/strong>&nbsp;<\/h4>\n\n\n\n<p><em>Art. 53. \u00c9 competente o foro:&nbsp;<\/em>&nbsp;<\/p>\n\n\n\n<p><em>I &#8211; para a&nbsp;<\/em><strong><em>a\u00e7\u00e3o de div\u00f3rcio, separa\u00e7\u00e3o, anula\u00e7\u00e3o de casamento e reconhecimento ou dissolu\u00e7\u00e3o de uni\u00e3o est\u00e1vel:&nbsp;<\/em><\/strong>&nbsp;<\/p>\n\n\n\n<p><em>a) de domic\u00edlio do&nbsp;<\/em><strong><em>guardi\u00e3o de filho incapaz;<\/em><\/strong><em>&nbsp;<\/em>&nbsp;<\/p>\n\n\n\n<p><em>b) do&nbsp;<\/em><strong><em>\u00faltimo domic\u00edlio do casal<\/em><\/strong><em>, caso n\u00e3o haja filho incapaz;&nbsp;<\/em>&nbsp;<\/p>\n\n\n\n<p><em>c) de&nbsp;<\/em><strong><em>domic\u00edlio do r\u00e9u,<\/em><\/strong><em>&nbsp;se nenhuma das partes residir no antigo domic\u00edlio do casal;&nbsp;<\/em>&nbsp;<\/p>\n\n\n\n<p><em>d) de&nbsp;<\/em><strong><em>domic\u00edlio da v\u00edtima de viol\u00eancia dom\u00e9stica&nbsp;<\/em><\/strong><em>e familiar.<\/em>&nbsp;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>12) Alimentos<\/strong>&nbsp;<\/h3>\n\n\n\n<p>O alimentando \u00e9 a crian\u00e7a ou adolescente que recebe alimentos de um dos pais. Por exemplo, a crian\u00e7a abandonada pelo pai, ajuizar a\u00e7\u00e3o para exigir alimentos do pai, por meio da representa\u00e7\u00e3o da m\u00e3e.&nbsp;<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>Regra:<\/strong>&nbsp;<\/h4>\n\n\n\n<p>A a\u00e7\u00e3o deve ser ajuizada no domic\u00edlio ou resid\u00eancia do alimentando.&nbsp;<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>Dispositivo Legal:<\/strong>&nbsp;<\/h4>\n\n\n\n<p><em>Art. 53. \u00c9 competente o foro:<\/em>&nbsp;<\/p>\n\n\n\n<p><em>II &#8211;&nbsp;<\/em><em>de<\/em><em>&nbsp;domic\u00edlio ou&nbsp;<\/em><strong><em>resid\u00eancia do alimentando, para a a\u00e7\u00e3o em que se pedem alimentos;<\/em><\/strong>&nbsp;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>13) Idoso<\/strong>&nbsp;<\/h3>\n\n\n\n<p>A\u00e7\u00f5es que versem sobre direito do idoso previsto no Estatuto do Idoso.&nbsp;<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>Regra:<\/strong>&nbsp;<\/h4>\n\n\n\n<p>Devem ser ajuizadas no local de resid\u00eancia do idoso.&nbsp;<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>Dispositivo Legal:<\/strong>&nbsp;<\/h4>\n\n\n\n<p><em>Art. 53. \u00c9 competente o foro:<\/em>&nbsp;<\/p>\n\n\n\n<p><em>III &#8211; do lugar:<\/em>&nbsp;<\/p>\n\n\n\n<p><em>e) de&nbsp;<\/em><strong><em>resid\u00eancia do idoso<\/em><\/strong><em>, para a causa que verse sobre&nbsp;<\/em><strong><em>direito previsto no respectivo estatuto<\/em><\/strong><em>;<\/em>&nbsp;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>14) Pessoa jur\u00eddica<\/strong>&nbsp;<\/h3>\n\n\n\n<p>A\u00e7\u00f5es em que pessoas jur\u00eddicas sejam r\u00e9s ou tenham&nbsp;contra\u00eddo&nbsp;obriga\u00e7\u00f5es.&nbsp;<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>Regras:<\/strong>&nbsp;<\/h4>\n\n\n\n<p>A) Se a pessoa jur\u00eddica for r\u00e9, a a\u00e7\u00e3o deve ser ajuizada no local de sua sede.&nbsp;<\/p>\n\n\n\n<p>B) A\u00e7\u00e3o envolvendo contrato em que a pessoa jur\u00eddica assumiu obriga\u00e7\u00f5es:&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>A a\u00e7\u00e3o pode ser ajuizada no local da sede; ou&nbsp;<\/li><\/ul>\n\n\n\n<ul class=\"wp-block-list\"><li>A a\u00e7\u00e3o pode ser ajuizada no local onde se encontra sua sucursal\/filial.&nbsp;<\/li><\/ul>\n\n\n\n<p><strong>Obs.:&nbsp;<\/strong>Nas a\u00e7\u00f5es que envolvem sociedade\/associa\u00e7\u00e3o SEM PERSONALIDADE JUR\u00cdDICA, o foro competente \u00e9 onde a entidade exerce suas atividades.&nbsp;<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>Dispositivo Legal:<\/strong>&nbsp;<\/h4>\n\n\n\n<p><em>Art. 53. \u00c9 competente o foro:<\/em>&nbsp;<\/p>\n\n\n\n<p><em>III &#8211; do lugar:&nbsp;<\/em>&nbsp;<\/p>\n\n\n\n<p><em>a) onde est\u00e1 a&nbsp;<\/em><strong><em>sede<\/em><\/strong><em>, para a a\u00e7\u00e3o em que for&nbsp;<\/em><strong><em>r\u00e9 pessoa jur\u00eddica;<\/em><\/strong><em>&nbsp;<\/em>&nbsp;<\/p>\n\n\n\n<p><em>b) onde se acha&nbsp;<\/em><strong><em>ag\u00eancia ou sucursal<\/em><\/strong><em>, quanto \u00e0s&nbsp;<\/em><strong><em>obriga\u00e7\u00f5es que a pessoa jur\u00eddica contraiu<\/em><\/strong><em>;&nbsp;<\/em>&nbsp;<\/p>\n\n\n\n<p><em>c) onde&nbsp;<\/em><strong><em>exerce suas atividades<\/em><\/strong><em>, para a a\u00e7\u00e3o em que for&nbsp;<\/em><strong><em>r\u00e9 sociedade ou associa\u00e7\u00e3o sem personalidade jur\u00eddica;<\/em><\/strong>&nbsp;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>15) Administrador ou gestor de neg\u00f3cio alheio<\/strong>&nbsp;<\/h3>\n\n\n\n<p>Trata-se de demandas em desfavor de administrador ou gestor de neg\u00f3cios de outra pessoa que causou dano em sua gest\u00e3o ou administra\u00e7\u00e3o.&nbsp;<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>Regra:<\/strong>&nbsp;<\/h4>\n\n\n\n<p>O foro ser\u00e1 do local do ato ou fato que gerou o dano.&nbsp;<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>Dispositivo Legal:<\/strong>&nbsp;<\/h4>\n\n\n\n<p><em>Art. 53.&nbsp;\u00c9 competente o foro:<\/em>&nbsp;<\/p>\n\n\n\n<p><em>IV &#8211;&nbsp;<\/em><em>do<\/em><em>&nbsp;lugar do&nbsp;<\/em><strong><em>ato ou fato para a a\u00e7\u00e3o<\/em><\/strong><em>:&nbsp;<\/em>&nbsp;<\/p>\n\n\n\n<p><em>b) em que for&nbsp;<\/em><strong><em>r\u00e9u administrador ou gestor de neg\u00f3cios alheios<\/em><\/strong><em>;<\/em>&nbsp;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>16) Execu\u00e7\u00f5es fiscais<\/strong>&nbsp;<\/h3>\n\n\n\n<p>Se uma pessoa n\u00e3o faz o pagamento de um tributo, h\u00e1 um lan\u00e7amento tribut\u00e1rio, que resulta, inicialmente, em cobran\u00e7a administrativa. No insucesso de cobran\u00e7a administrativa, a Receita Federal constitui a certid\u00e3o de d\u00edvida ativa, que \u00e9 um t\u00edtulo executivo extrajudicial. Esse t\u00edtulo \u00e9 exigido judicialmente pela Procuradoria da Fazenda Nacional, por interm\u00e9dio de uma execu\u00e7\u00e3o fiscal.&nbsp;<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>Regra:&nbsp;<\/strong>&nbsp;<\/h4>\n\n\n\n<p>O ajuizamento da execu\u00e7\u00e3o fiscal pode ser feito:&nbsp;<\/p>\n\n\n\n<p>A) No foro do domic\u00edlio do r\u00e9u;&nbsp;&nbsp;<\/p>\n\n\n\n<p>B) No local de resid\u00eancia do r\u00e9u; ou&nbsp;<\/p>\n\n\n\n<p>C) No local onde for encontrado o r\u00e9u.&nbsp;<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>Dispositivo Legal:<\/strong>&nbsp;<\/h4>\n\n\n\n<p><em>Art.46 \u00a7 5\u00ba A&nbsp;<\/em><strong><em>execu\u00e7\u00e3o fiscal&nbsp;<\/em><\/strong><em>ser\u00e1 proposta no foro de<\/em><strong><em>&nbsp;domic\u00edlio do r\u00e9u, no de sua resid\u00eancia ou no do lugar onde for encontrado.<\/em><\/strong>&nbsp;<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Demais regras de compet\u00eancia do Processo Civil<\/strong>&nbsp;<\/h2>\n\n\n\n<p>Hoje, estudamos as regras gerais e as regras de fixa\u00e7\u00e3o de compet\u00eancia, presentes no CPC. \u00c9 imprescind\u00edvel a compreens\u00e3o e memoriza\u00e7\u00e3o desses dispositivos, que aparecem reiteradamente em provas de concurso. As regras de modifica\u00e7\u00e3o de compet\u00eancia e as regras de incompet\u00eancia ser\u00e3o objeto dos pr\u00f3ximos artigos.&nbsp;<\/p>\n\n\n\n<p>Achou esse artigo&nbsp;\u00fatil? Deixe seu coment\u00e1rio.&nbsp;&nbsp;<\/p>\n\n\n\n<p>Um forte abra\u00e7o e at\u00e9 o pr\u00f3ximo tema de Direito Processual Civil!&nbsp;&nbsp;<\/p>\n\n\n\n<p>Ana Luiza Tib\u00farcio.&nbsp;<\/p>\n\n\n\n<p><strong>Instagram:&nbsp;<\/strong><a href=\"https:\/\/www.instagram.com\/anatiburcio\/\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/www.instagram.com\/anatiburcio\/<\/a>&nbsp;&nbsp;<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong><em>Assinatura Anual Ilimitada*<\/em><\/strong>&nbsp;&nbsp;<\/h2>\n\n\n\n<p><em>Prepare-se com&nbsp;o&nbsp;melhor material e com quem mais aprova em Concursos P\u00fablicos em todo&nbsp;o&nbsp;pa\u00eds. Assine agora a nossa Assinatura Anual e tenha acesso&nbsp;ilimitado* a todos&nbsp;os nossos cursos.<\/em>&nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"has-text-align-center has-vivid-green-cyan-background-color has-background\"><strong>ASSINE AGORA<\/strong>&nbsp;\u2013&nbsp;<a href=\"https:\/\/www.estrategiaconcursos.com.br\/assinaturas\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Assinatura Ilimitada<\/strong><\/a>&nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"has-text-align-center has-luminous-vivid-amber-background-color has-background\"><strong>SISTEMA DE QUEST\u00d5ES \u2013&nbsp;<\/strong><a href=\"https:\/\/questoes.estrategiaconcursos.com.br\/\" target=\"_blank\" rel=\"noreferrer noopener\">Experimente Gr\u00e1tis por 7 dias<\/a>&nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"has-text-align-center\"><strong><em>Fique por dentro&nbsp;de todos&nbsp;os concursos<\/em><\/strong>:&nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"has-text-align-center has-black-color has-vivid-cyan-blue-background-color has-text-color has-background\"><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-abertos\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Concursos abertos<\/strong><\/a>&nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"has-text-align-center has-black-color has-pale-cyan-blue-background-color has-text-color has-background\"><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-2020\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Concursos 2020<\/strong><\/a>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Entenda quais s\u00e3o os t\u00f3picos mais importantes no que tange \u00e0s Regras de Compet\u00eancia do Processo Civil e direcione seus estudos, focando nos assuntos que costumam ser cobradas nas provas de concursos.&nbsp;&nbsp; Esse artigo faz parte da s\u00e9rie de resumos de Direito Processual Civil, em que est\u00e3o sendo apresentados os principais temas do&nbsp;C\u00f3digo de Processo [&hellip;]<\/p>\n","protected":false},"author":1666,"featured_media":597855,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"post_tipo":"article","footnotes":""},"categories":[1],"tags":[],"tax_estado":[],"class_list":["post-597832","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cursos-e-concursos"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.2 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Regras de Compet\u00eancia do C\u00f3digo de Processo Civil \u2013 Parte I<\/title>\n<meta name=\"description\" content=\"Entenda quais s\u00e3o os t\u00f3picos mais importantes no que tange \u00e0s Regras de Compet\u00eancia do Processo Civil e direcione seus estudos.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/regras-de-competencia-do-cpc\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Regras de Compet\u00eancia do C\u00f3digo de Processo Civil \u2013 Parte I\" \/>\n<meta property=\"og:description\" content=\"Entenda quais s\u00e3o os t\u00f3picos mais importantes no que tange \u00e0s Regras de Compet\u00eancia do Processo Civil e direcione seus estudos.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/regras-de-competencia-do-cpc\/\" \/>\n<meta property=\"og:site_name\" content=\"Estrat\u00e9gia Concursos\" \/>\n<meta property=\"article:published_time\" content=\"2020-11-04T18:23:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/10\/28102216\/juiz.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"602\" \/>\n\t<meta property=\"og:image:height\" content=\"297\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Ana Luiza Tib\u00farcio Guimar\u00e3es\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:site\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ana Luiza Tib\u00farcio Guimar\u00e3es\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"23 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/regras-de-competencia-do-cpc\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/regras-de-competencia-do-cpc\/\"},\"author\":{\"name\":\"Ana Luiza Tib\u00farcio Guimar\u00e3es\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/adbd974f815a3acb9e572fdf7315d7c2\"},\"headline\":\"Regras de Compet\u00eancia do C\u00f3digo de Processo Civil \u2013 Parte I\",\"datePublished\":\"2020-11-04T18:23:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/regras-de-competencia-do-cpc\/\"},\"wordCount\":4688,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/regras-de-competencia-do-cpc\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/10\/28102216\/juiz.jpg\",\"articleSection\":[\"Concursos P\u00fablicos\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/regras-de-competencia-do-cpc\/#respond\"]}],\"copyrightYear\":\"2020\",\"copyrightHolder\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/regras-de-competencia-do-cpc\/\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/regras-de-competencia-do-cpc\/\",\"name\":\"Regras de Compet\u00eancia do C\u00f3digo de Processo Civil \u2013 Parte I\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/regras-de-competencia-do-cpc\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/regras-de-competencia-do-cpc\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/10\/28102216\/juiz.jpg\",\"datePublished\":\"2020-11-04T18:23:00+00:00\",\"description\":\"Entenda quais s\u00e3o os t\u00f3picos mais importantes no que tange \u00e0s Regras de Compet\u00eancia do Processo Civil e direcione seus estudos.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/regras-de-competencia-do-cpc\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/regras-de-competencia-do-cpc\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/regras-de-competencia-do-cpc\/#primaryimage\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/10\/28102216\/juiz.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/10\/28102216\/juiz.jpg\",\"width\":602,\"height\":297,\"caption\":\"direito processual penal para concursos\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/regras-de-competencia-do-cpc\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Regras de Compet\u00eancia do C\u00f3digo de Processo Civil \u2013 Parte I\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"name\":\"Estrat\u00e9gia Concursos\",\"description\":\"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.\",\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\",\"name\":\"Estrat\u00e9gia Concursos\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"width\":230,\"height\":60,\"caption\":\"Estrat\u00e9gia Concursos\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/EstratConcursos\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/adbd974f815a3acb9e572fdf7315d7c2\",\"name\":\"Ana Luiza Tib\u00farcio Guimar\u00e3es\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/d0e9fa767d159d6bdb59324855854ef2672e0774dce8705b1c42c80a5b4de7b8?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/d0e9fa767d159d6bdb59324855854ef2672e0774dce8705b1c42c80a5b4de7b8?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/d0e9fa767d159d6bdb59324855854ef2672e0774dce8705b1c42c80a5b4de7b8?s=96&d=mm&r=g\",\"caption\":\"Ana Luiza Tib\u00farcio Guimar\u00e3es\"},\"description\":\"Graduada em Direito pela Pontif\u00edcia Universidade Cat\u00f3lica de Minas Gerais e graduada em Ci\u00eancias do Estado pela Universidade Federal de Minas Gerais. P\u00f3s Graduada em Direito P\u00fablico pela PUC Minas. Gradua\u00e7\u00e3o em Gest\u00e3o P\u00fablica e P\u00f3s Gradua\u00e7\u00e3o em Ci\u00eancia Pol\u00edtica em andamento. Analista de Processo Legislativo do Senado Federal, lotada na Secretaria Legislativa do Senado. Aprova\u00e7\u00f5es em concursos: Aprovada para o cargo de Analista Judici\u00e1ria do TRF 3 (2025) Aprovada para o cargo de Procuradora do Munic\u00edpio de S\u00e3o Paulo (2024) Aprovada para o cargo de Analista Legislativa do Senado Federal (2023) Aprovada em 1\u00ba lugar para o cargo de T\u00e9cnico Judici\u00e1rio do TRF 3 (2019) Aprovada para o cargo de Juiz Leigo do Tribunal de Justi\u00e7a de Minas Gerais (2019).\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/anatiburcio-ggmail-com\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Regras de Compet\u00eancia do C\u00f3digo de Processo Civil \u2013 Parte I","description":"Entenda quais s\u00e3o os t\u00f3picos mais importantes no que tange \u00e0s Regras de Compet\u00eancia do Processo Civil e direcione seus estudos.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.estrategiaconcursos.com.br\/blog\/regras-de-competencia-do-cpc\/","og_locale":"pt_BR","og_type":"article","og_title":"Regras de Compet\u00eancia do C\u00f3digo de Processo Civil \u2013 Parte I","og_description":"Entenda quais s\u00e3o os t\u00f3picos mais importantes no que tange \u00e0s Regras de Compet\u00eancia do Processo Civil e direcione seus estudos.","og_url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/regras-de-competencia-do-cpc\/","og_site_name":"Estrat\u00e9gia Concursos","article_published_time":"2020-11-04T18:23:00+00:00","og_image":[{"width":602,"height":297,"url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/10\/28102216\/juiz.jpg","type":"image\/jpeg"}],"author":"Ana Luiza Tib\u00farcio Guimar\u00e3es","twitter_card":"summary_large_image","twitter_creator":"@EstratConcursos","twitter_site":"@EstratConcursos","twitter_misc":{"Escrito por":"Ana Luiza Tib\u00farcio Guimar\u00e3es","Est. tempo de leitura":"23 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/regras-de-competencia-do-cpc\/#article","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/regras-de-competencia-do-cpc\/"},"author":{"name":"Ana Luiza Tib\u00farcio Guimar\u00e3es","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/adbd974f815a3acb9e572fdf7315d7c2"},"headline":"Regras de Compet\u00eancia do C\u00f3digo de Processo Civil \u2013 Parte I","datePublished":"2020-11-04T18:23:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/regras-de-competencia-do-cpc\/"},"wordCount":4688,"commentCount":0,"publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/regras-de-competencia-do-cpc\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/10\/28102216\/juiz.jpg","articleSection":["Concursos P\u00fablicos"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/regras-de-competencia-do-cpc\/#respond"]}],"copyrightYear":"2020","copyrightHolder":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/regras-de-competencia-do-cpc\/","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/regras-de-competencia-do-cpc\/","name":"Regras de Compet\u00eancia do C\u00f3digo de Processo Civil \u2013 Parte I","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/regras-de-competencia-do-cpc\/#primaryimage"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/regras-de-competencia-do-cpc\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/10\/28102216\/juiz.jpg","datePublished":"2020-11-04T18:23:00+00:00","description":"Entenda quais s\u00e3o os t\u00f3picos mais importantes no que tange \u00e0s Regras de Compet\u00eancia do Processo Civil e direcione seus estudos.","breadcrumb":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/regras-de-competencia-do-cpc\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/regras-de-competencia-do-cpc\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/regras-de-competencia-do-cpc\/#primaryimage","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/10\/28102216\/juiz.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/10\/28102216\/juiz.jpg","width":602,"height":297,"caption":"direito processual penal para concursos"},{"@type":"BreadcrumbList","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/regras-de-competencia-do-cpc\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.estrategiaconcursos.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Regras de Compet\u00eancia do C\u00f3digo de Processo Civil \u2013 Parte I"}]},{"@type":"WebSite","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","name":"Estrat\u00e9gia Concursos","description":"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.","publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization","name":"Estrat\u00e9gia Concursos","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","width":230,"height":60,"caption":"Estrat\u00e9gia Concursos"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/EstratConcursos"]},{"@type":"Person","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/adbd974f815a3acb9e572fdf7315d7c2","name":"Ana Luiza Tib\u00farcio Guimar\u00e3es","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/d0e9fa767d159d6bdb59324855854ef2672e0774dce8705b1c42c80a5b4de7b8?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/d0e9fa767d159d6bdb59324855854ef2672e0774dce8705b1c42c80a5b4de7b8?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d0e9fa767d159d6bdb59324855854ef2672e0774dce8705b1c42c80a5b4de7b8?s=96&d=mm&r=g","caption":"Ana Luiza Tib\u00farcio Guimar\u00e3es"},"description":"Graduada em Direito pela Pontif\u00edcia Universidade Cat\u00f3lica de Minas Gerais e graduada em Ci\u00eancias do Estado pela Universidade Federal de Minas Gerais. P\u00f3s Graduada em Direito P\u00fablico pela PUC Minas. Gradua\u00e7\u00e3o em Gest\u00e3o P\u00fablica e P\u00f3s Gradua\u00e7\u00e3o em Ci\u00eancia Pol\u00edtica em andamento. Analista de Processo Legislativo do Senado Federal, lotada na Secretaria Legislativa do Senado. Aprova\u00e7\u00f5es em concursos: Aprovada para o cargo de Analista Judici\u00e1ria do TRF 3 (2025) Aprovada para o cargo de Procuradora do Munic\u00edpio de S\u00e3o Paulo (2024) Aprovada para o cargo de Analista Legislativa do Senado Federal (2023) Aprovada em 1\u00ba lugar para o cargo de T\u00e9cnico Judici\u00e1rio do TRF 3 (2019) Aprovada para o cargo de Juiz Leigo do Tribunal de Justi\u00e7a de Minas Gerais (2019).","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/anatiburcio-ggmail-com\/"}]}},"_links":{"self":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/597832","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/users\/1666"}],"replies":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/comments?post=597832"}],"version-history":[{"count":13,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/597832\/revisions"}],"predecessor-version":[{"id":600287,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/597832\/revisions\/600287"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media\/597855"}],"wp:attachment":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media?parent=597832"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/categories?post=597832"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tags?post=597832"},{"taxonomy":"tax_estado","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tax_estado?post=597832"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}