{"id":582768,"date":"2020-10-04T19:20:59","date_gmt":"2020-10-04T22:20:59","guid":{"rendered":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?p=582768"},"modified":"2020-10-04T19:25:10","modified_gmt":"2020-10-04T22:25:10","slug":"prova-eaoar-2021-analise-das-questoes","status":"publish","type":"post","link":"https:\/\/www.estrategiaconcursos.com.br\/blog\/prova-eaoar-2021-analise-das-questoes\/","title":{"rendered":"Prova EAOAR 2021 &#8211; An\u00e1lise das Quest\u00f5es"},"content":{"rendered":"\n<p>Ol\u00e1 pessoal,<\/p>\n\n\n\n<p>Temos at\u00e9 amanh\u00e3, dia 5\/10, para enviar os recursos contra as quest\u00f5es da nossa prova.<\/p>\n\n\n\n<p>Em an\u00e1lise da prova, com a ajuda e colabora\u00e7\u00e3o de v\u00e1rios alunos, encontramos algumas quest\u00f5es pass\u00edveis de contesta\u00e7\u00e3o, cujos coment\u00e1rios seguem abaixo. <\/p>\n\n\n\n<p>Os alunos do curso j\u00e1 t\u00eam acesso a esses coment\u00e1rios na aula extra 36.<\/p>\n\n\n\n<p>Boa sorte nos recursos!<\/p>\n\n\n\n<p>Coment\u00e1rios e dicas adicionais s\u00e3o publicados no Instagram: @profmarcuscampiteli<\/p>\n\n\n\n<p>Os n\u00fameros das quest\u00f5es correspondem \u00e0 Prova A.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><a>Quest\u00e3o 33<\/a><\/h2>\n\n\n\n<p><strong>As obras de arte s\u00e3o as constru\u00e7\u00f5es em Engenharia Civil que tem o objetivo de assegurar, como parte de rede vi\u00e1rias, a circula\u00e7\u00e3o de pessoas, de ve\u00edculos ou produtos. O termo sublinhado pode ter como exemplo as\/os<\/strong><\/p>\n\n\n\n<p><strong>a) p\u00f3rticos.<\/strong><\/p>\n\n\n\n<p><strong>b) rodovias.<\/strong><\/p>\n\n\n\n<p><strong>c) barragens.<\/strong><\/p>\n\n\n\n<p><strong>d) aquedutos.<\/strong><\/p>\n\n\n\n<p><strong>Coment\u00e1rios:<\/strong><\/p>\n\n\n\n<p>Esta quest\u00e3o acaba sendo pol\u00eamica, pois em outra quest\u00e3o desta prova (quest\u00e3o 56 da Prova A e 58 da prova B) as barragens s\u00e3o classificadas como obras de arte. Este fato acaba por confundir os candidatos quanto ao gabarito objetivo desta quest\u00e3o. Com isso, recomenda-se a anula\u00e7\u00e3o desta quest\u00e3o.<\/p>\n\n\n\n<p><strong>Gabarito Preliminar Oficial: D<\/strong><\/p>\n\n\n\n<p><strong>Gabarito Proposto: Anula\u00e7\u00e3o<\/strong><\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><a>Quest\u00e3o 36<\/a><\/h2>\n\n\n\n<p><strong>Nos pa\u00edses em desenvolvimento e emergentes, a principal preocupa\u00e7\u00e3o \u00e9 criar infraestrutura como rodovias. Ao construir novas estradas, \u00e9 importante criar um bloco de revestimento bem interligado, desde uma camada de base est\u00e1vel at\u00e9 uma camada de superf\u00edcie rodovi\u00e1ria nivelada e perfilada com precis\u00e3o.<\/strong><\/p>\n\n\n\n<p><strong>A esse respeito, avalie as afirmativas.<\/strong><\/p>\n\n\n\n<p><strong>I. Uma das aplica\u00e7\u00f5es cl\u00e1ssicas, para fins de garantia de vida \u00fatil na constru\u00e7\u00e3o de estradas, s\u00e3o a camada de sinaliza\u00e7\u00e3o e a camada de prote\u00e7\u00e3o contra o congelamento.<\/strong><\/p>\n\n\n\n<p><strong>II. A camada de base de uma estrada deve ser capaz de suportar uma grande variedade de condi\u00e7\u00f5es meteorol\u00f3gicas.<\/strong><\/p>\n\n\n\n<p><strong>III. Uma das aplica\u00e7\u00f5es da camada de prote\u00e7\u00e3o contra o congelamento \u00e9 proteger para que a \u00e1gua n\u00e3o penetre no corpo da estrada.<\/strong><\/p>\n\n\n\n<p><strong>IV. Uma das camadas finais da constru\u00e7\u00e3o de uma estrada \u00e9 a compacta\u00e7\u00e3o que se destina a criar uma estrutura plana e uniforme.<\/strong><\/p>\n\n\n\n<p><strong>Est\u00e3o corretas apenas o que se afirma em<\/strong><\/p>\n\n\n\n<p><strong>a) I, II e III.<\/strong><\/p>\n\n\n\n<p><strong>b) I, II e IV.<\/strong><\/p>\n\n\n\n<p><strong>c) I, III e IV.<\/strong><\/p>\n\n\n\n<p><strong>d) II, III e IV.<\/strong><\/p>\n\n\n\n<p><strong>Coment\u00e1rios:<\/strong><\/p>\n\n\n\n<p>Entendo que o item IV desta quest\u00e3o apresenta erro ao confundir ou fazer confundir a opera\u00e7\u00e3o de compacta\u00e7\u00e3o com uma camada propriamente dita.<\/p>\n\n\n\n<p>Desta forma, os itens corretos seriam o II e III, n\u00e3o havendo op\u00e7\u00e3o, pelo que se recomenda a anula\u00e7\u00e3o desta quest\u00e3o.<\/p>\n\n\n\n<p><strong>Gabarito Preliminar Oficial: D<\/strong><\/p>\n\n\n\n<p><strong>Gabarito Proposto: Anula\u00e7\u00e3o<\/strong><\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><a>Quest\u00e3o 40<\/a><\/h2>\n\n\n\n<p><strong>Leia o texto a seguir.<\/strong><\/p>\n\n\n\n<p><strong>Classifica\u00e7\u00e3o PEI para pisos cer\u00e2micos<\/strong><\/p>\n\n\n\n<p><strong>O PEI (Porcelain Emanel Institute) \u00e9 a sigla que representa o nome do instituto que regulamentou as normas para a classifica\u00e7\u00e3o de resist\u00eancia \u00e0 abras\u00e3o, ou seja, ao desgaste superficial da superf\u00edcie esmaltada causada, principalmente, pelo tr\u00e1fego de pessoas. \u00c9 o PEI, que conforme norma, orienta que tipo de cer\u00e2mica utilizar em um determinado ambiente. Quanto maior o PEI, maior \u00e9 a resist\u00eancia da cer\u00e2mica ao desgaste, ao efeito abrasivo.<\/strong><\/p>\n\n\n\n<p><strong>(Dispon\u00edvel em: &lt;https:\/\/pedreirao.com.br\/pei-das-ceramicas-passo-a-passo\/&gt;. Acesso em: 04\/03\/2020. Modificado)<\/strong><\/p>\n\n\n\n<p><strong>Com rela\u00e7\u00e3o ao texto acima, \u00e9 correto afirmar que a\/o<\/strong><\/p>\n\n\n\n<p><strong>a) porcelanato t\u00e9cnico, por n\u00e3o ser esmaltado, n\u00e3o possui a classifica\u00e7\u00e3o PEI.<\/strong><\/p>\n\n\n\n<p><strong>b) classifica\u00e7\u00e3o PEI-2 \u00e9 recomendada para ambientes de tr\u00e2nsito baixo de pessoas.<\/strong><\/p>\n\n\n\n<p><strong>c) classifica\u00e7\u00e3o PEI-3 \u00e9 recomendada para ambientes de tr\u00e2nsito intenso de pessoas.<\/strong><\/p>\n\n\n\n<p><strong>d) material n\u00e3o esmaltado, como a rocha, possui outro ensaio de abras\u00e3o superficial para determina\u00e7\u00e3o do desgaste.<\/strong><\/p>\n\n\n\n<p><strong>Coment\u00e1rios:<\/strong><\/p>\n\n\n\n<p>O item B tamb\u00e9m pode ser considerado correto, pois o piso de classifica\u00e7\u00e3o PEI-2 \u00e9 de fato recomendado para ambientes de baixo tr\u00e2nsito de pessoas, conforme, por exemplo, consta nos sites &lt;<a href=\"http:\/\/todacasanet.com.br\/wptc\/porcelanato-tem-pei\/\">http:\/\/todacasanet.com.br\/wptc\/porcelanato-tem-pei\/<\/a>&gt;.<\/p>\n\n\n\n<p>E o item D tamb\u00e9m pode ser considerado correto, tendo em vista que a resist\u00eancia \u00e0 abras\u00e3o \u00e9 de grande import\u00e2ncia para as placas p\u00e9treas, conforme se pode verificar em &lt; https:\/\/www.sindirochas.com\/arquivos\/guia-de-aplicacao-de-rochas-em-revestimentos.pdf &gt;, assim como em &lt; <a href=\"https:\/\/icposgrados.weebly.com\/uploads\/8\/6\/0\/0\/860075\/f.pdf\">https:\/\/icposgrados.weebly.com\/uploads\/8\/6\/0\/0\/860075\/f.pdf<\/a>&gt;, e h\u00e1 ensaio de abras\u00e3o apropriado para materiais p\u00e9treos, previsto pela norma da ABNT NBR 12042 \u2013 Materiais Inorg\u00e2nicos \u2013 Determina\u00e7\u00e3o do desgaste por abras\u00e3o, conforme mencionado em ambos os artigos (p. 32 e p. 186, respectivamente).<\/p>\n\n\n\n<p><strong>Gabarito Oficial Preliminar: A<\/strong><\/p>\n\n\n\n<p><strong>Gabarito Proposto: Anula\u00e7\u00e3o<\/strong><\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><a>Quest\u00e3o 42<\/a><\/h2>\n\n\n\n<p><strong>Informe se \u00e9 verdadeiro (V) ou falso (F) o que se afirma a seguir sobre solos.<\/strong><\/p>\n\n\n\n<p><strong>( ) Define-se como resist\u00eancia ao cisalhamento do solo a tens\u00e3o cisalhante que ocorre no plano de ruptura no instante da ruptura.<\/strong><\/p>\n\n\n\n<p><strong>( ) O ensaio de cisalhamento direto em solos \u00e9 repetido para tr\u00eas ou mais corpos de prova id\u00eanticos, utilizando valores diferentes de carga.<\/strong><\/p>\n\n\n\n<p><strong>( ) Solos n\u00e3o coesivos caracterizam-se pelo comportamento no cisalhamento ditado pelo imbricamento e a aus\u00eancia de atrito entre as part\u00edculas.<\/strong><\/p>\n\n\n\n<p><strong>( ) Para a redu\u00e7\u00e3o de volume e massa de um solo saturado h\u00e1 a necessidade de sa\u00edda de \u00e1gua nos vazios do solo.<\/strong><\/p>\n\n\n\n<p><strong>A sequ\u00eancia correta \u00e9<\/strong><\/p>\n\n\n\n<p><strong>a) (V); (V); (F); (F).<\/strong><\/p>\n\n\n\n<p><strong>b) (F); (V); (F); (V).<\/strong><\/p>\n\n\n\n<p><strong>c) (F); (F); (V); (V).<\/strong><\/p>\n\n\n\n<p><strong>d) (V); (F); (V); (F).<\/strong><\/p>\n\n\n\n<p><strong>Coment\u00e1rios:<\/strong><\/p>\n\n\n\n<p>No item D verifica-se um texto confuso quando menciona a \u201cnecessidade de sa\u00edda de \u00e1gua nos vazios do solo\u201d, pois se mostra sem sentido, pois n\u00e3o se consegue imaginar ou encontrar paralelo na literatura sobre a ideia de sa\u00edda de \u00e1gua nos vazios do solo. O que se tem na literatura e na pr\u00e1tica da engenharia \u00e9 a sa\u00edda de \u00e1gua dos vazios do solo. Desta foram, esse erro de reda\u00e7\u00e3o acabou por prejudicar a objetividade da quest\u00e3o.<\/p>\n\n\n\n<p><strong>Gabarito Preliminar Oficial: A<\/strong><\/p>\n\n\n\n<p><strong>Gabarito Proposto: Anula\u00e7\u00e3o<\/strong><\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><a>Quest\u00e3o 43<\/a><\/h2>\n\n\n\n<p><strong>Permite estimar a carga para a qual ocorre a fissura\u00e7\u00e3o e, desse modo, predizer a durabilidade do concreto quanto a sua utiliza\u00e7\u00e3o em pavimentos, tirantes e em reservat\u00f3rios cil\u00edndricos, onde a principal solicita\u00e7\u00e3o \u00e9 a de tra\u00e7\u00e3o pura. Qual o ensaio de controle tecnol\u00f3gico que determina essa propriedade no concreto?<\/strong><\/p>\n\n\n\n<p><strong>a) Ensaio de resist\u00eancia \u00e0 flex\u00e3o.<\/strong><\/p>\n\n\n\n<p><strong>b) Ensaio de resist\u00eancia \u00e0 compress\u00e3o.<\/strong><\/p>\n\n\n\n<p><strong>c) Ensaio de resist\u00eancia ao cisalhamento.<\/strong><\/p>\n\n\n\n<p><strong>d) Ensaio de resist\u00eancia \u00e0 compress\u00e3o diametral (Ensaio de \u201cLobo Carneiro\u201d).<\/strong><\/p>\n\n\n\n<p><strong>Coment\u00e1rios:<\/strong><\/p>\n\n\n\n<p>Nesta quest\u00e3o pode-se interpretar que h\u00e1 dois gabaritos corretos: A e D, pois ambos os ensaios permitem a determina\u00e7\u00e3o da resist\u00eancia \u00e0 tra\u00e7\u00e3o do concreto, conforme previsto na norma ABNT NBR 6118\/2014 &#8211; Projeto de estruturas de concreto \u2013 Procedimento, no subitem 8.2.5 \u2013 Resist\u00eancia \u00e0 tra\u00e7\u00e3o:<\/p>\n\n\n\n<p>\u201cA resist\u00eancia \u00e0 tra\u00e7\u00e3o indireta fct,sp e a resist\u00eancia \u00e0 tra\u00e7\u00e3o na flex\u00e3o fct,f devem ser obtidas em ensaios realizados segundo as ABNT NBR 7222 e ABNT NBR 12142, respectivamente.<\/p>\n\n\n\n<p>A resist\u00eancia \u00e0 tra\u00e7\u00e3o direta fct pode ser considerada igual a 0,9 fct,sp ou 0,7 fct,f, ou, na falta de ensaios para obten\u00e7\u00e3o de fct,sp e fct,f, pode ser avaliado o seu valor m\u00e9dio ou caracter\u00edstico por meio das seguintes equa\u00e7\u00f5es &#8230;\u201d<\/p>\n\n\n\n<p>A norma ABNT NBR 7222 destina-se \u00e0 determina\u00e7\u00e3o da resist\u00eancia \u00e0 tra\u00e7\u00e3o por compress\u00e3o diametral de corpos de prova cil\u00edndricos de concretos e argamassas, e a norma ABNT NBR 12142 destina-se \u00e0 determina\u00e7\u00e3o da resist\u00eancia \u00e0 tra\u00e7\u00e3o na flex\u00e3o de corpos de prova Prism\u00e1ticos de concreto.<\/p>\n\n\n\n<p><strong>Gabarito Preliminar Oficial: D<\/strong><\/p>\n\n\n\n<p><strong>Gabarito Proposto: Anula\u00e7\u00e3o<\/strong><\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><a>Quest\u00e3o 44<\/a><\/h2>\n\n\n\n<p><strong>O conjunto de medidas que tem como objetivo minimizar os riscos que a popula\u00e7\u00e3o est\u00e1 sujeita, diminuir os preju\u00edzos causados por inunda\u00e7\u00f5es e possibilitar o desenvolvimento urbano de forma harm\u00f4nica, articulada e sustent\u00e1vel \u00e9 uma das atribui\u00e7\u00f5es de medidas em torno da<\/strong><\/p>\n\n\n\n<p><strong>a) pavimenta\u00e7\u00e3o.<\/strong><\/p>\n\n\n\n<p><strong>b) a\u00e7\u00e3o urban\u00edstica.<\/strong><\/p>\n\n\n\n<p><strong>c) drenagem urbana.<\/strong><\/p>\n\n\n\n<p><strong>d) pol\u00edtica de saneamento b\u00e1sico.<\/strong><\/p>\n\n\n\n<p><strong>Coment\u00e1rios:<\/strong><\/p>\n\n\n\n<p>Verifica-se que o enunciado se enquadra como drenagem urbana, contudo, a drenagem urbana faz parte da pol\u00edtica de saneamento b\u00e1sico, prevista na Lei 11.445\/2007, conforme se verifica no seu artigo 3\u00ba-D:<\/p>\n\n\n\n<p>\u201cArt. 3\u00ba-D. Consideram-se servi\u00e7os p\u00fablicos de manejo das \u00e1guas pluviais urbanas aqueles constitu\u00eddos por 1 (uma) ou mais das seguintes atividades:<\/p>\n\n\n\n<p>I &#8211; drenagem urbana;<\/p>\n\n\n\n<p>II &#8211; transporte de \u00e1guas pluviais urbanas;<\/p>\n\n\n\n<p>III &#8211; deten\u00e7\u00e3o ou reten\u00e7\u00e3o de \u00e1guas pluviais urbanas para amortecimento de vaz\u00f5es de cheias; e<\/p>\n\n\n\n<p>IV &#8211; tratamento e disposi\u00e7\u00e3o final de \u00e1guas pluviais urbanas.<\/p>\n\n\n\n<p><strong>Gabarito Preliminar Oficial: C<\/strong><\/p>\n\n\n\n<p><strong>Gabarito Proposto: Anula\u00e7\u00e3o<\/strong><\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><a>Quest\u00e3o 47<\/a><\/h2>\n\n\n\n<p><strong>Analise as asser\u00e7\u00f5es a seguir e a rela\u00e7\u00e3o proposta entre elas.<\/strong><\/p>\n\n\n\n<p><strong>I. O vidro pode oferecer muitos benef\u00edcios aos projetos arquitet\u00f4nicos. Entre eles est\u00e3o a integra\u00e7\u00e3o de ambientes, conforto t\u00e9rmico e ac\u00fastico, ilumina\u00e7\u00e3o natural, seguran\u00e7a e privacidade<\/strong><\/p>\n\n\n\n<p><strong>PORQUE<\/strong><\/p>\n\n\n\n<p><strong>II. antes da lamina\u00e7\u00e3o com tr\u00eas ou quatro camadas de PVB, o vidro temperado vai assegurar elevada resist\u00eancia \u00e0 pe\u00e7a, al\u00e9m de conforto ac\u00fastico e excelente prote\u00e7\u00e3o contra os raios UV.<\/strong><\/p>\n\n\n\n<p><strong>\u00c9 correto afirmar que<\/strong><\/p>\n\n\n\n<p><strong>a) a primeira \u00e9 uma afirmativa falsa; e a segunda, verdadeira.<\/strong><\/p>\n\n\n\n<p><strong>b) a primeira \u00e9 uma afirmativa verdadeira; e a segunda, falsa.<\/strong><\/p>\n\n\n\n<p><strong>c) as duas s\u00e3o verdadeiras, mas n\u00e3o estabelecem rela\u00e7\u00e3o entre si.<\/strong><\/p>\n\n\n\n<p><strong>d) as duas s\u00e3o verdadeiras, e a segunda \u00e9 uma justificativa correta da primeira.<\/strong><\/p>\n\n\n\n<p><strong>Coment\u00e1rios:<\/strong><\/p>\n\n\n\n<p>De acordo com Bauer, \u201cal\u00e9m do aspecto da seguran\u00e7a, o vidro laminado apresenta propriedades que o diferenciam dos vidros recozidos ou temperados.<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Os vidros de seguran\u00e7a laminados s\u00e3o excelentes filtros de raios ultravioleta, reduzindo em 99,6% ou mais a transmiss\u00e3o desses raios, conforme Tab. 28.5.<\/p>\n\n\n\n<p>(&#8230;)<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Aliando a massa da l\u00e2mina de vidro ao efeito amortecedor da pel\u00edcula de polivinil butiral, os vidros de seguran\u00e7a laminados melhoram o desempenho ac\u00fastico de um envidra\u00e7amento. A pel\u00edcula de PVB, em fun\u00e7\u00e3o de sua alta flexibilidade, absorve e amortece as vibra\u00e7\u00f5es sonoras transmitidas pela l\u00e2mina de vidro externa, reduzindo a transmiss\u00e3o sonora para o interior do ambiente. Essa caracter\u00edstica torna-se particularmente interessante para as frequ\u00eancias de 1000 a 2000 Hz, onde ocorre o fen\u00f4meno da \u201ccoincid\u00eancia\u201d para os vidros monol\u00edticos. Nessa faixa de frequ\u00eancia, correspondente aos ru\u00eddos de tr\u00e1fego e avi\u00f5es, os vidros monol\u00edticos praticamente passam a vibrar na mesma frequ\u00eancia da fonte sonora, permitindo a passagem de grande parte dessas vibra\u00e7\u00f5es. A interposi\u00e7\u00e3o da pel\u00edcula de PVB atenua significativamente esse efeito de coincid\u00eancia e melhora o desempenho do envidra\u00e7amento nas frequ\u00eancias mais altas (buzinas de carro, avi\u00f5es a jato), conforme se v\u00ea no diagrama mostrado na Fig. 28.21.<\/p>\n\n\n\n<p>(&#8230;)\u201d<\/p>\n\n\n\n<p>Fonte:<\/p>\n\n\n\n<p>&#8211; Ver\u00e7osa, Enio Jos\u00e9 &amp; Bauer, L.A. Falc\u00e3o (coordenador). Materiais de Constru\u00e7\u00e3o \u2013 Vol. II \u2013 Cap\u00edtulo 28 \u2013 Vidro, p. 876-877. Rio de Janeiro. LTC, 2012.<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Portanto, verifica-se que o conforto ac\u00fastico e a excelente prote\u00e7\u00e3o contra os raios UV s\u00e3o obtidos ap\u00f3s a lamina\u00e7\u00e3o com tr\u00eas ou quatro camadas de PVB, e n\u00e3o antes como consta na segunda afirmativa, o que a torna incorreta.<\/p>\n\n\n\n<p><strong>Gabarito Preliminar Oficial: C<\/strong><\/p>\n\n\n\n<p><strong>Gabarito Proposto: Anula\u00e7\u00e3o<\/strong><\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><a>Quest\u00e3o 49<\/a><\/h2>\n\n\n\n<p><strong>49) Leia o texto a seguir.<\/strong><\/p>\n\n\n\n<p><strong>Um dos assuntos mais importantes durante a constru\u00e7\u00e3o de uma obra s\u00e3o as instala\u00e7\u00f5es el\u00e9tricas. N\u00e3o somente por elas serem de extrema import\u00e2ncia para a rotina da sua casa ou empreendimento comercial, j\u00e1 que a eletricidade \u00e9 a principal fonte de luz, causando uma grande depend\u00eancia desta para as mais diversas tarefas do nosso dia a dia, mas tamb\u00e9m para a seguran\u00e7a dos usu\u00e1rios.<\/strong><\/p>\n\n\n\n<p><strong>(Dispon\u00edvel em: &lt;https:\/\/portejr.com.br\/instalacoes-eletricas\/&gt;. Acesso em: 04\/03\/2020. Modificado)<\/strong><\/p>\n\n\n\n<p><strong>Com rela\u00e7\u00e3o \u00e0s instala\u00e7\u00f5es el\u00e9tricas prediais, \u00e9 correto afirmar que<\/strong><\/p>\n\n\n\n<p><strong>a) os circuitos el\u00e9tricos para instala\u00e7\u00f5es residenciais podem manter em um mesmo circuito as tomadas e ilumina\u00e7\u00e3o.<\/strong><\/p>\n\n\n\n<p><strong>b) as instala\u00e7\u00f5es el\u00e9tricas mal dimensionadas ou mau executadas podem trazer diversos transtornos durante a concep\u00e7\u00e3o do projeto.<\/strong><\/p>\n\n\n\n<p><strong>c) os servi\u00e7os de instala\u00e7\u00f5es el\u00e9tricas necessitam de cabos e fios de qualidade e disjuntores, item essencial para o funcionamento de um sistema el\u00e9trico.<\/strong><\/p>\n\n\n\n<p><strong>d) o cabo UTP e o conector RJ45 s\u00e3o usados como padr\u00e3o durante a instala\u00e7\u00e3o, colaborando para a transmiss\u00e3o e distribui\u00e7\u00e3o da energia el\u00e9trica na resid\u00eancia.<\/strong><\/p>\n\n\n\n<p><strong>Coment\u00e1rios:<\/strong><\/p>\n\n\n\n<p>A norma ABNT ABNT 5410 &#8211; Instala\u00e7\u00f5es el\u00e9tricas de baixa tens\u00e3o, prev\u00ea que:<\/p>\n\n\n\n<p>\u201cOs circuitos terminais devem ser individualizados pela fun\u00e7\u00e3o dos equipamentos de utiliza\u00e7\u00e3o que alimentam. Em particular, devem ser previstos circuitos terminais distintos para pontos de ilumina\u00e7\u00e3o e para pontos de tomada.<\/p>\n\n\n\n<p>(&#8230;)<\/p>\n\n\n\n<p>9.5.3.2 Os pontos de tomada de cozinhas, copas, copas-cozinhas, \u00e1reas de servi\u00e7o, lavanderias e locais an\u00e1logos devem ser atendidos por circuitos exclusivamente destinados \u00e0 alimenta\u00e7\u00e3o de tomadas desses locais.<\/p>\n\n\n\n<p><strong>9.5.3.3 Em locais de habita\u00e7\u00e3o, admite-se, como exce\u00e7\u00e3o \u00e0 regra geral de 4.2.5.5, que pontos de tomada<\/strong>, exceto aqueles indicados em 9.5.3.2, <strong>e pontos de ilumina\u00e7\u00e3o possam ser alimentados por circuito comum,<\/strong> desde que as seguintes condi\u00e7\u00f5es sejam simultaneamente atendidas:<\/p>\n\n\n\n<p>a) a corrente de projeto (IB) do circuito comum (ilumina\u00e7\u00e3o mais tomadas) n\u00e3o deve ser superior a 16 A;<\/p>\n\n\n\n<p>b) os pontos de ilumina\u00e7\u00e3o n\u00e3o sejam alimentados, em sua totalidade, por um s\u00f3 circuito, caso esse circuito seja comum (ilumina\u00e7\u00e3o mais tomadas); e<\/p>\n\n\n\n<p>c) os pontos de tomadas, j\u00e1 exclu\u00eddos os indicados em 9.5.3.2, n\u00e3o sejam alimentados, em sua totalidade, por um s\u00f3 circuito, caso esse circuito seja comum (ilumina\u00e7\u00e3o mais tomadas).\u201d<\/p>\n\n\n\n<p>Portanto, verifica-se que, de acordo com a norma ABNT NBR 5410 o item A tamb\u00e9m est\u00e1 correto.<\/p>\n\n\n\n<p><strong>Gabarito Preliminar Oficial: C<\/strong><\/p>\n\n\n\n<p><strong>Gabarito Proposto: Anula\u00e7\u00e3o<\/strong><\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><a>Quest\u00e3o 60<\/a><\/h2>\n\n\n\n<p><strong>Leia o texto a seguir.<\/strong><\/p>\n\n\n\n<p><strong>Ferramentas de planejamento de empreendimentos civis<\/strong><\/p>\n\n\n\n<p><strong>O sucesso em projetos de Constru\u00e7\u00e3o Civil caracteriza-se pela atua\u00e7\u00e3o permanente do gestor na programa\u00e7\u00e3o e controle de seus empreendimentos. Portanto, a fim de alcan\u00e7ar uma boa administra\u00e7\u00e3o, a necessidade em adotar t\u00e9cnicas gerenciais apropriadas se torna evidente. Assim, por meio delas, buscam-se adequa\u00e7\u00f5es \u00e0 incertezas, inconst\u00e2ncias de habilidades e recursos envolvidos e ciclo de vida do empreendimento.<\/strong><\/p>\n\n\n\n<p><strong>(Dispon\u00edvel em: &lt;https:\/\/www.guiadaengenharia.com\/curva-s-engenharia\/&gt;. Acesso em: 04\/03\/2020. Modificado)<\/strong><\/p>\n\n\n\n<p><strong>Referente ao planejamento de empreendimentos civis com a ferramenta da curva S, \u00e9 correto afirmar que a curva S<\/strong><\/p>\n\n\n\n<p><strong>a) n\u00e3o pode ser elaborada com n\u00fameros absolutos, s\u00f3 em percentuais.<\/strong><\/p>\n\n\n\n<p><strong>b) \u00e9 uma ferramenta gerencial que fornece dados que permitem um comparativo entre planejado x realizado.<\/strong><\/p>\n\n\n\n<p><strong>c) em termos pr\u00e1ticos, nos permite visualizar o qu\u00e3o distante uma execu\u00e7\u00e3o est\u00e1 daquilo que realmente foi executado.<\/strong><\/p>\n\n\n\n<p><strong>d) \u00e9 uma representa\u00e7\u00e3o da soma unit\u00e1ria de parcelas<\/strong><\/p>\n\n\n\n<p><strong>Coment\u00e1rios:<\/strong><\/p>\n\n\n\n<p>De acordo com Mattos (2010), no cap\u00edtulo sobre a An\u00e1lise de Valor Agregado ou EVA (earned value analysis), ensina que o m\u00e9todo EVA compara o valor do trabalho planejado com o do trabalho realmente conclu\u00eddo para avaliar se os desempenhos de custo e programa\u00e7\u00e3o do empreendimento est\u00e3o de acordo com o planejado, por meio de indicadores de desempenho, que permitem antever o resultado prov\u00e1vel do projeto em termos de custo e prazo.<\/p>\n\n\n\n<p>O ponto de partida para a implementa\u00e7\u00e3o do EVA \u00e9 o cronograma f\u00edsico-financeiro. Este se baseia em uma EAP e gera como subproduto a curva S de custos, conforme a figura a seguir. A curva S serve de par\u00e2metro para a an\u00e1lise da rela\u00e7\u00e3o entre o valor agregado e o valor planejado do trabalho em um dado per\u00edodo.<\/p>\n\n\n\n<p>O Valor Agregado (VA) representa o custo or\u00e7ado do trabalho realizado. O VA refere-se ao custo or\u00e7ado e n\u00e3o se relaciona com o custo real, ou seja, \u00e9 o custo do que foi executado com base nos pre\u00e7os planilhados e n\u00e3o nos pre\u00e7os de mercado atualizados.<\/p>\n\n\n\n<p>E o Valor Previsto (VP) \u00e9 o custo que deveria ter sido incorrido no per\u00edodo de aferi\u00e7\u00e3o. Ele corresponde ao custo or\u00e7ado do trabalho agendado (ou planejado), ou seja, calculado de acordo com o or\u00e7amento\/planejamento da obra. O VP n\u00e3o tem nada a ver com o que foi fisicamente realizado. Ele corresponde \u00e0 linha de base.<\/p>\n\n\n\n<p>Ainda de acordo com Mattos (2010), a curva S feita no in\u00edcio do projeto representa a linha de base (baseline), que \u00e9 a refer\u00eancia com a qual se compara o progresso realizado.<\/p>\n\n\n\n<p>Fonte:<\/p>\n\n\n\n<p>&#8211; Mattos, Aldo D\u00f3rea. Planejamento e Controle de Obras. Cap\u00edtulo 18, p. 353-359. S\u00e3o Paulo: PINI, 2010.<\/p>\n\n\n\n<p>Portanto, verifica-se que a Curva S pode ser considerada como uma ferramenta gerencial que fornece dados que permitem um comparativo entre planejado x realizado.<\/p>\n\n\n\n<p><strong>Gabarito Preliminar Oficial: C<\/strong><\/p>\n\n\n\n<p><strong>Gabarito proposto: Anula\u00e7\u00e3o<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ol\u00e1 pessoal, Temos at\u00e9 amanh\u00e3, dia 5\/10, para enviar os recursos contra as quest\u00f5es da nossa prova. Em an\u00e1lise da prova, com a ajuda e colabora\u00e7\u00e3o de v\u00e1rios alunos, encontramos algumas quest\u00f5es pass\u00edveis de contesta\u00e7\u00e3o, cujos coment\u00e1rios seguem abaixo. Os alunos do curso j\u00e1 t\u00eam acesso a esses coment\u00e1rios na aula extra 36. Boa sorte [&hellip;]<\/p>\n","protected":false},"author":74,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"post_tipo":"article","footnotes":""},"categories":[1],"tags":[219897,137534,806,70],"tax_estado":[],"class_list":["post-582768","post","type-post","status-publish","format-standard","hentry","category-cursos-e-concursos","tag-aeronautica","tag-eaoear","tag-engenharia","tag-engenharia-civil"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.2 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Prova EAOAR 2021 - An\u00e1lise das Quest\u00f5es<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/prova-eaoar-2021-analise-das-questoes\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Prova EAOAR 2021 - An\u00e1lise das Quest\u00f5es\" \/>\n<meta property=\"og:description\" content=\"Ol\u00e1 pessoal, Temos at\u00e9 amanh\u00e3, dia 5\/10, para enviar os recursos contra as quest\u00f5es da nossa prova. Em an\u00e1lise da prova, com a ajuda e colabora\u00e7\u00e3o de v\u00e1rios alunos, encontramos algumas quest\u00f5es pass\u00edveis de contesta\u00e7\u00e3o, cujos coment\u00e1rios seguem abaixo. Os alunos do curso j\u00e1 t\u00eam acesso a esses coment\u00e1rios na aula extra 36. Boa sorte [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/prova-eaoar-2021-analise-das-questoes\/\" \/>\n<meta property=\"og:site_name\" content=\"Estrat\u00e9gia Concursos\" \/>\n<meta property=\"article:published_time\" content=\"2020-10-04T22:20:59+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-10-04T22:25:10+00:00\" \/>\n<meta name=\"author\" content=\"Marcus Campiteli\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:site\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Marcus Campiteli\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"14 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/prova-eaoar-2021-analise-das-questoes\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/prova-eaoar-2021-analise-das-questoes\/\"},\"author\":{\"name\":\"Marcus Campiteli\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/0d6c3568ad3bba68a36b50cc46d9fe45\"},\"headline\":\"Prova EAOAR 2021 &#8211; An\u00e1lise das Quest\u00f5es\",\"datePublished\":\"2020-10-04T22:20:59+00:00\",\"dateModified\":\"2020-10-04T22:25:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/prova-eaoar-2021-analise-das-questoes\/\"},\"wordCount\":2871,\"commentCount\":1,\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"keywords\":[\"aeron\u00e1utica\",\"eaoear\",\"Engenharia\",\"Engenharia Civil\"],\"articleSection\":[\"Concursos P\u00fablicos\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/prova-eaoar-2021-analise-das-questoes\/#respond\"]}],\"copyrightYear\":\"2020\",\"copyrightHolder\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/prova-eaoar-2021-analise-das-questoes\/\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/prova-eaoar-2021-analise-das-questoes\/\",\"name\":\"Prova EAOAR 2021 - An\u00e1lise das Quest\u00f5es\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\"},\"datePublished\":\"2020-10-04T22:20:59+00:00\",\"dateModified\":\"2020-10-04T22:25:10+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/prova-eaoar-2021-analise-das-questoes\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/prova-eaoar-2021-analise-das-questoes\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/prova-eaoar-2021-analise-das-questoes\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Prova EAOAR 2021 &#8211; An\u00e1lise das Quest\u00f5es\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"name\":\"Estrat\u00e9gia Concursos\",\"description\":\"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.\",\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\",\"name\":\"Estrat\u00e9gia Concursos\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"width\":230,\"height\":60,\"caption\":\"Estrat\u00e9gia Concursos\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/EstratConcursos\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/0d6c3568ad3bba68a36b50cc46d9fe45\",\"name\":\"Marcus Campiteli\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/23cce70184e951a7dc3567ad9d82fdce792f50ac238a408c7cff09c7bac2973e?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/23cce70184e951a7dc3567ad9d82fdce792f50ac238a408c7cff09c7bac2973e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/23cce70184e951a7dc3567ad9d82fdce792f50ac238a408c7cff09c7bac2973e?s=96&d=mm&r=g\",\"caption\":\"Marcus Campiteli\"},\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/marcuscampiteliestrategiaconcursos-com-br\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Prova EAOAR 2021 - An\u00e1lise das Quest\u00f5es","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.estrategiaconcursos.com.br\/blog\/prova-eaoar-2021-analise-das-questoes\/","og_locale":"pt_BR","og_type":"article","og_title":"Prova EAOAR 2021 - An\u00e1lise das Quest\u00f5es","og_description":"Ol\u00e1 pessoal, Temos at\u00e9 amanh\u00e3, dia 5\/10, para enviar os recursos contra as quest\u00f5es da nossa prova. Em an\u00e1lise da prova, com a ajuda e colabora\u00e7\u00e3o de v\u00e1rios alunos, encontramos algumas quest\u00f5es pass\u00edveis de contesta\u00e7\u00e3o, cujos coment\u00e1rios seguem abaixo. Os alunos do curso j\u00e1 t\u00eam acesso a esses coment\u00e1rios na aula extra 36. Boa sorte [&hellip;]","og_url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/prova-eaoar-2021-analise-das-questoes\/","og_site_name":"Estrat\u00e9gia Concursos","article_published_time":"2020-10-04T22:20:59+00:00","article_modified_time":"2020-10-04T22:25:10+00:00","author":"Marcus Campiteli","twitter_card":"summary_large_image","twitter_creator":"@EstratConcursos","twitter_site":"@EstratConcursos","twitter_misc":{"Escrito por":"Marcus Campiteli","Est. tempo de leitura":"14 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/prova-eaoar-2021-analise-das-questoes\/#article","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/prova-eaoar-2021-analise-das-questoes\/"},"author":{"name":"Marcus Campiteli","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/0d6c3568ad3bba68a36b50cc46d9fe45"},"headline":"Prova EAOAR 2021 &#8211; An\u00e1lise das Quest\u00f5es","datePublished":"2020-10-04T22:20:59+00:00","dateModified":"2020-10-04T22:25:10+00:00","mainEntityOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/prova-eaoar-2021-analise-das-questoes\/"},"wordCount":2871,"commentCount":1,"publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"keywords":["aeron\u00e1utica","eaoear","Engenharia","Engenharia Civil"],"articleSection":["Concursos P\u00fablicos"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/prova-eaoar-2021-analise-das-questoes\/#respond"]}],"copyrightYear":"2020","copyrightHolder":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/prova-eaoar-2021-analise-das-questoes\/","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/prova-eaoar-2021-analise-das-questoes\/","name":"Prova EAOAR 2021 - An\u00e1lise das Quest\u00f5es","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website"},"datePublished":"2020-10-04T22:20:59+00:00","dateModified":"2020-10-04T22:25:10+00:00","breadcrumb":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/prova-eaoar-2021-analise-das-questoes\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/prova-eaoar-2021-analise-das-questoes\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/prova-eaoar-2021-analise-das-questoes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.estrategiaconcursos.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Prova EAOAR 2021 &#8211; An\u00e1lise das Quest\u00f5es"}]},{"@type":"WebSite","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","name":"Estrat\u00e9gia Concursos","description":"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.","publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization","name":"Estrat\u00e9gia Concursos","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","width":230,"height":60,"caption":"Estrat\u00e9gia Concursos"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/EstratConcursos"]},{"@type":"Person","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/0d6c3568ad3bba68a36b50cc46d9fe45","name":"Marcus Campiteli","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/23cce70184e951a7dc3567ad9d82fdce792f50ac238a408c7cff09c7bac2973e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/23cce70184e951a7dc3567ad9d82fdce792f50ac238a408c7cff09c7bac2973e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/23cce70184e951a7dc3567ad9d82fdce792f50ac238a408c7cff09c7bac2973e?s=96&d=mm&r=g","caption":"Marcus Campiteli"},"url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/marcuscampiteliestrategiaconcursos-com-br\/"}]}},"_links":{"self":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/582768","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/users\/74"}],"replies":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/comments?post=582768"}],"version-history":[{"count":2,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/582768\/revisions"}],"predecessor-version":[{"id":582778,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/582768\/revisions\/582778"}],"wp:attachment":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media?parent=582768"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/categories?post=582768"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tags?post=582768"},{"taxonomy":"tax_estado","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tax_estado?post=582768"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}