{"id":56597,"date":"2016-12-02T17:52:00","date_gmt":"2016-12-02T20:52:00","guid":{"rendered":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?p=56597"},"modified":"2021-02-24T12:00:32","modified_gmt":"2021-02-24T15:00:32","slug":"administracao-direta-e-indireta","status":"publish","type":"post","link":"https:\/\/www.estrategiaconcursos.com.br\/blog\/administracao-direta-e-indireta\/","title":{"rendered":"Administra\u00e7\u00e3o direta e indireta &#8211; Dica Estrat\u00e9gica &#8211; Direito Adminitrativo"},"content":{"rendered":"<p style=\"text-align: justify;\"><em><strong>Diferen\u00e7a entre Administra\u00e7\u00e3o direta e indireta &#8211; Dica Estrat\u00e9gica &#8211; Direito Adminitrativo<\/strong><\/em><\/p>\n<p style=\"text-align: justify;\">Ol\u00e1 amigos, tudo bem? Aqui \u00e9 o Prof. Herbert Almeida. Hoje, vamos iniciar a nossa <img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-56556\" title=\"administra\u00e7\u00e3o direta e indireta\" src=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-content\/uploads\/2016\/11\/dicas-estrategicas-2-06-1-300x122.png\" alt=\"dicas-estrategicas-2-06-1\" width=\"300\" height=\"122\" \/>participa\u00e7\u00e3o no projeto de Dicas Estrat\u00e9gicas do Estrat\u00e9gia Concursos.<\/p>\n<p style=\"text-align: justify;\">O assunto que vamos falar\u00a0n\u00e3o \u00e9 t\u00e3o complicado, mas aparece MUITO em provas de concursos p\u00fablicos, de todas as bancas. Falaremos, ent\u00e3o, da <strong>Administra\u00e7\u00e3o direta e indireta<\/strong>.<\/p>\n<p style=\"text-align: justify;\">A express\u00e3o Administra\u00e7\u00e3o P\u00fablica possui v\u00e1rios sentidos, mas o que nos interessa, neste momento, \u00e9 o conceito <span style=\"color: #0000ff;\"><strong>estrito<\/strong><span style=\"color: #000000;\">,<\/span><\/span>\u00a0em <span style=\"color: #0000ff;\"><strong>sentido subjetivo, formal ou org\u00e2nico<\/strong><\/span>, segundo o qual a Administra\u00e7\u00e3o P\u00fablica \u00e9\u00a0o <strong><span style=\"text-decoration: underline;\">conjunto de pessoas jur\u00eddicas, \u00f3rg\u00e3os e agentes p\u00fablicos<\/span> que exercem a <em>fun\u00e7\u00e3o administrativa<\/em>. Portanto, corresponde ao \u201c<span style=\"color: #0000ff;\">quem<\/span>\u201d exerce tal fun\u00e7\u00e3o<\/strong>.<\/p>\n<p style=\"text-align: justify;\">Com efeito, a <span style=\"color: #0000ff;\"><em><strong>fun\u00e7\u00e3o administrativa<\/strong> <\/em><\/span>\u00e9\u00a0instrumento de realiza\u00e7\u00e3o direta e imediata dos direitos fundamentais, por meio do qual a Administra\u00e7\u00e3o P\u00fablica executa as leis para prestar servi\u00e7os \u00e0 popula\u00e7\u00e3o ou gerencia a m\u00e1quina administrativa. Por exemplo: quando um \u00f3rg\u00e3o faz uma licita\u00e7\u00e3o p\u00fablica, estar\u00e1 exercendo a fun\u00e7\u00e3o administrativa. Da mesma forma, quando o INSS\u00a0presta o atendimento de segurados do regime geral\u00a0de previd\u00eancia social, estar\u00e1 exercendo a fun\u00e7\u00e3o administrativa. Por fim, quando um empresa p\u00fablica presta o servi\u00e7o p\u00fablico de distribui\u00e7\u00e3o de energia el\u00e9trica, estar\u00e1 exercendo a fun\u00e7\u00e3o administrativa.<\/p>\n<p style=\"text-align: justify;\">Ainda nesse contexto, podemos\u00a0ter em mente que, classicamente, o sentido formal considera os agentes, \u00f3rg\u00e3os e pessoas jur\u00eddicas encarregados da atividade administrativa.<\/p>\n<p style=\"text-align: justify;\">Em que pese a fun\u00e7\u00e3o administrativa seja realizada principalmente\u00a0pelos \u00f3rg\u00e3os do Poder Executivo, precisamos saber que h\u00e1 \u00f3rg\u00e3os respons\u00e1veis por essa fun\u00e7\u00e3o nos demais poderes. Assim, as \u201csecretarias\u201d ou \u201cmesas\u201d encarregadas da fun\u00e7\u00e3o administrativa nos Poderes Legislativo e Judici\u00e1rio tamb\u00e9m se enquadram no conceito subjetivo. Da mesma forma,\u00a0os Tribunais de Contas e o Minist\u00e9rio P\u00fablico, quando exercem a fun\u00e7\u00e3o administrativa (ex.: quando realizam um concurso p\u00fablico para ingresso de servidores), tamb\u00e9m\u00a0se enquadram no conceito subjetivo, formal ou org\u00e2nico.<\/p>\n<p style=\"text-align: justify;\">Esses \u00f3rg\u00e3os integrantes dos Poderes e respons\u00e1veis pela fun\u00e7\u00e3o administrativa fazem parte da <span style=\"color: #0000ff;\"><strong>Administra\u00e7\u00e3o direta ou centralizada<\/strong><\/span>, pois est\u00e3o subordinados diretamente \u00e0s <strong>pessoas jur\u00eddicas pol\u00edticas<\/strong> (Uni\u00e3o, estados, munic\u00edpios e Distrito Federal).<\/p>\n<p style=\"text-align: justify;\">Contudo, devemos saber que a fun\u00e7\u00e3o administrativa n\u00e3o \u00e9 realizada somente de forma centralizada. As entidades pol\u00edticas podem criar <strong>entes descentralizados<\/strong>, as chamadas <strong>entidades administrativas<\/strong>, que s\u00e3o entes com personalidade jur\u00eddica pr\u00f3pria e que formam a <span style=\"color: #0000ff;\"><strong>Administra\u00e7\u00e3o indireta ou descentralizada<\/strong><\/span>. No Brasil, os entes administrativos s\u00e3o: <strong>autarquias, funda\u00e7\u00f5es p\u00fablicas, empresas p\u00fablicas e sociedades de economia mista<\/strong>.<\/p>\n<p style=\"text-align: justify;\">Portanto, podemos dizer que a express\u00e3o \u201cAdministra\u00e7\u00e3o P\u00fablica\u201d, em sentido formal, subjetivo ou org\u00e2nico, compreende os <strong>agentes p\u00fablicos, os \u00f3rg\u00e3os da Administra\u00e7\u00e3o direta e as entidades integrantes da Administra\u00e7\u00e3o indireta<\/strong>.<\/p>\n<p style=\"text-align: justify;\">Sem querer aprofundar muito, ou ainda confundi-los, devemos observar que o conceito de Administra\u00e7\u00e3o P\u00fablica, majoritariamente adotado pela doutrina, n\u00e3o \u00e9 t\u00e3o preciso assim! <em>Como assim, professor, voc\u00ea est\u00e1 nos dizendo que a doutrina n\u00e3o apresente um conceito t\u00e9cnico sobre o tema?<\/em> \u00c9 mais ou menos isso!<\/p>\n<p style=\"text-align: justify;\">Se lev\u00e1ssemos o conceito apresentado acima ao &#8220;p\u00e9 da letra&#8221;, tamb\u00e9m estaria abrangido pelo conceito subjetivo, formal ou org\u00e2nico as <strong><em>entidades privadas, prestadoras de servi\u00e7os p\u00fablicos<\/em><\/strong>. Refiro-me, aqui, especialmente \u00e0s concession\u00e1rias e \u00e0s permission\u00e1rias de servi\u00e7os p\u00fablicos (ex.: empresas de telefonia: Oi, Vivo, Tim, Claro, etc.), uma vez que, quando est\u00e3o atuando na presta\u00e7\u00e3o desses servi\u00e7os, tais empresas estar\u00e3o exercendo a <em><strong>fun\u00e7\u00e3o administrativa<\/strong><\/em>.<\/p>\n<p style=\"text-align: justify;\">Ocorre que, na verdade, o conceito subjetivo, formal ou org\u00e2nico <span style=\"color: #ff0000;\"><strong>N\u00c3O<\/strong><\/span> inclui essas entidades. Vale dizer, as empresas privadas, que prestam servi\u00e7os mediante delega\u00e7\u00e3o,\u00a0<strong><span style=\"color: #ff0000;\">N\u00c3O<\/span>\u00a0integram a Administra\u00e7\u00e3o P\u00fablica em sentido formal<\/strong>.<\/p>\n<p style=\"text-align: justify;\">Por esse motivo, Marcelo Alexandrino e Vicente Paulo definem Administra\u00e7\u00e3o P\u00fablica, em sentido formal, como o\u00a0\u201c<em>conjunto de \u00f3rg\u00e3os, pessoas jur\u00eddicas e agentes que o nosso ordenamento jur\u00eddico identifica como administra\u00e7\u00e3o p\u00fablica, <strong>n\u00e3o importa a atividade que exer\u00e7am<\/strong><\/em>\u201d.<\/p>\n<p style=\"text-align: justify;\">Portanto, para eles, a natureza da atividade \u00e9 irrelevante, pois o Brasil adota o crit\u00e9rio formal, segundo o qual \u00e9 Administra\u00e7\u00e3o P\u00fablica aquilo que o nosso direito assim considera.<\/p>\n<p style=\"text-align: justify;\">Ressalto, contudo, que, para fins de prova, tanto um, como o outro conceito poder\u00e1 aparecer. O que nos importa \u00e9 que o conceito subjetivo, formal ou org\u00e2nico trata &#8220;das pessoas&#8221; que exercem a fun\u00e7\u00e3o administrativa, exclu\u00eddas as entidades privadas que prestam servi\u00e7os p\u00fablicos por delega\u00e7\u00e3o.<\/p>\n<p style=\"text-align: justify;\">Al\u00e9m disso, a Administra\u00e7\u00e3o direta \u00e9 formada pelos \u00f3rg\u00e3os subordinados diretamente \u00e0s pessoas pol\u00edticas. No \u00e2mbito federal, por exemplo,\u00a0integram a Administra\u00e7\u00e3o direta a Presid\u00eancia da Rep\u00fablica, os Minist\u00e9rios, os \u00f3rg\u00e3os subordinados aos minist\u00e9rios (exemplo: Secretaria da Receita Federal, Pol\u00edcia Federal, etc.),\u00a0a C\u00e2mara dos Deputados e seus \u00f3rg\u00e3os administrativos, o STF, demais tribunais do Judici\u00e1rio, etc. Nos munic\u00edpios, s\u00e3o exemplos de \u00f3rg\u00e3os da Administra\u00e7\u00e3o direta a prefeitura municipal, as secretarias municipais e as c\u00e2maras municipais. Enfim, os \u00f3rg\u00e3os que integram as pessoas pol\u00edticas (isto \u00e9, a Uni\u00e3o, os estados, o Distrito Federal e os munic\u00edpios), independentemente do Poder, fazem parte da Administra\u00e7\u00e3o direta ou centralizada.<\/p>\n<p style=\"text-align: justify;\">Por outro lado, a Administra\u00e7\u00e3o indireta ou descentralizada \u00e9 formada pelas entidades administrativas, ou seja, pelas <span style=\"color: #0000ff;\"><strong>autarquias,<\/strong> <strong>funda\u00e7\u00f5es p\u00fablicas<\/strong>, <strong>empresas p\u00fablicas<\/strong> e <strong>sociedades de economia mista<\/strong><\/span>.<\/p>\n<p style=\"text-align: justify;\">Tais entidades s\u00e3o criadas pelas pessoas pol\u00edticas, como mecanismos de especializa\u00e7\u00e3o, para que prestem determinada atividade espec\u00edfica, com maior autonomia em rela\u00e7\u00e3o ao ente central.<\/p>\n<p style=\"text-align: justify;\">Sobre o tema, \u00e9 indispens\u00e1vel a leitura do art. 37,\u00a0XIX, que estabelece que:<\/p>\n<blockquote>\n<p style=\"text-align: justify;\"><em>XIX &#8211; somente por lei espec\u00edfica poder\u00e1 ser criada <span style=\"color: #0000ff;\"><strong>autarquia<\/strong><\/span> e autorizada a institui\u00e7\u00e3o de <span style=\"color: #0000ff;\"><strong>empresa p\u00fablica<\/strong><\/span>, de <span style=\"color: #0000ff;\"><strong>sociedade de economia mista<\/strong><\/span> e de <span style=\"color: #0000ff;\"><strong>funda\u00e7\u00e3o<\/strong><\/span>, cabendo \u00e0 lei complementar, neste \u00faltimo caso, definir as \u00e1reas de sua atua\u00e7\u00e3o; <\/em><\/p>\n<\/blockquote>\n<p style=\"text-align: justify;\">Portanto, as autarquias s\u00e3o efetivamente criadas por lei, motivo pelo qual possuem personalidade jur\u00eddica de <strong>direito p\u00fablico<\/strong>.<\/p>\n<p style=\"text-align: justify;\">Por outro lado, a cria\u00e7\u00e3o de empresas p\u00fablicas e de sociedades de economia mista \u00e9 <strong>autorizada<\/strong> por lei, sendo que a efetiva cria\u00e7\u00e3o ocorrer\u00e1 por um ato posterior,\u00a0isto \u00e9, pelo registro do ato\u00a0de cria\u00e7\u00e3o no \u00f3rg\u00e3o competente. Assim, essas entidades possuem personalidade de <strong>direito privado<\/strong>.<\/p>\n<p style=\"text-align: justify;\">Por fim, a institui\u00e7\u00e3o das <strong>funda\u00e7\u00f5es p\u00fablicas<\/strong>, ao &#8220;p\u00e9 da letra&#8221; do texto constitucional, seria autorizada por lei espec\u00edfica. Contudo, o STF j\u00e1 decidiu que, atualmente, podem ser criadas funda\u00e7\u00f5es de <strong>direito p\u00fablico<\/strong> e de <strong>direito privado<\/strong>. As primeiras, seriam criadas por lei, ao passo que as de direito privado teriam a cria\u00e7\u00e3o autorizada em lei.<\/p>\n<p style=\"text-align: justify;\">Observa-se, ainda, que a &#8220;lei complementar&#8221; mencionada no art. 37, XIX, n\u00e3o serve para criar as funda\u00e7\u00f5es. Estas s\u00e3o criadas ou autorizadas por lei espec\u00edfica, isto \u00e9, por uma lei ordin\u00e1ria. A &#8220;lei complementar&#8221;, n\u00e3o editada at\u00e9 hoje, servir\u00e1 para definir as \u00e1reas de atua\u00e7\u00e3o dessas entidades.<\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-56600 size-full\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2016\/12\/01113938\/cria%C3%A7%C3%A3o-entidades-administrativas.jpg\" alt=\"administra\u00e7\u00e3o direta e indireta\" width=\"1231\" height=\"420\" srcset=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2016\/12\/01113938\/cria%C3%A7%C3%A3o-entidades-administrativas.jpg 1231w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2016\/12\/01113938\/cria%C3%A7%C3%A3o-entidades-administrativas.jpg 300w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2016\/12\/01113938\/cria%C3%A7%C3%A3o-entidades-administrativas.jpg 768w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2016\/12\/01113938\/cria%C3%A7%C3%A3o-entidades-administrativas.jpg 1024w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2016\/12\/01113938\/cria%C3%A7%C3%A3o-entidades-administrativas.jpg 500w\" sizes=\"auto, (max-width: 1231px) 100vw, 1231px\" \/><\/p>\n<p style=\"text-align: justify;\">Ap\u00f3s abordar parte da cria\u00e7\u00e3o, vejamos os conceitos dessas entidades:<\/p>\n<ul style=\"text-align: justify;\">\n<li class=\"Corpotexto\" style=\"text-align: justify;\"><strong><span style=\"color: #0000ff;\">autarquia<\/span>:<\/strong> pessoa jur\u00eddica de <strong>direito p\u00fablico<\/strong>, criada por lei, com capacidade de autoadministra\u00e7\u00e3o, para o desempenho de servi\u00e7o p\u00fablico descentralizado, mediante controle administrativo exercido nos limites da lei (Prof. Maria Sylvia Zanella Di Pietro);<\/li>\n<\/ul>\n<ul style=\"text-align: justify;\">\n<li class=\"Corpotexto\" style=\"text-align: justify;\"><span style=\"color: #0000ff;\"><strong>funda\u00e7\u00e3o p\u00fablica<\/strong><\/span>: \u00e9 a\u00a0funda\u00e7\u00e3o institu\u00edda pelo Poder P\u00fablico como o <strong>patrim\u00f4nio, total ou parcialmente p\u00fablico, dotado de personalidade jur\u00eddica<\/strong> de direito p\u00fablico ou privado e destinado, por lei, ao desempenho de atividades do Estado de ordem social, com capacidade de autoadministra\u00e7\u00e3o e mediante controle da Administra\u00e7\u00e3o P\u00fablica, nos limites da lei (Prof. Maria Sylvia Zanella Di Pietro);<\/li>\n<\/ul>\n<ul style=\"text-align: justify;\">\n<li class=\"Corpotexto\" style=\"text-align: justify;\"><span style=\"color: #0000ff;\"><strong>empresa p\u00fablica<\/strong><\/span>:\u00a0\u00e9 a entidade dotada de personalidade jur\u00eddica de <strong>direito privado<\/strong>, com cria\u00e7\u00e3o autorizada por lei e com <strong>patrim\u00f4nio pr\u00f3prio<\/strong>, cujo capital social \u00e9 integralmente detido pela Uni\u00e3o, pelos Estados, pelo Distrito Federal ou pelos Munic\u00edpios. Ademais,\u00a0desde que a maioria do capital votante permane\u00e7a em propriedade do ente pol\u00edtico, ser\u00e1 admitida, no capital da empresa p\u00fablica, a participa\u00e7\u00e3o de outras pessoas jur\u00eddicas de direito p\u00fablico interno, bem como de entidades da administra\u00e7\u00e3o indireta da Uni\u00e3o, dos Estados, do Distrito Federal e dos Munic\u00edpios (Lei 13.303\/16, art. 3\u00ba);<\/li>\n<\/ul>\n<ul style=\"text-align: justify;\">\n<li class=\"Corpotexto\" style=\"text-align: justify;\"><span style=\"color: #0000ff;\"><strong>sociedade de economia mista<\/strong><\/span>:\u00a0\u00e9 a entidade dotada de personalidade jur\u00eddica de <strong>direito privado<\/strong>, com cria\u00e7\u00e3o autorizada por lei, sob a forma de <strong>sociedade an\u00f4nima<\/strong>, cujas a\u00e7\u00f5es com direito a voto <strong>perten\u00e7am em sua maioria<\/strong> \u00e0 Uni\u00e3o, aos Estados, ao Distrito Federal, aos Munic\u00edpios ou a entidade da administra\u00e7\u00e3o indireta (Lei 13.303\/16, art. 4\u00ba).<\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Nessa linha, as autarquias representam, basicamente, um bra\u00e7o, ou prolongamento da Administra\u00e7\u00e3o direta, uma vez que\u00a0possuem\u00a0natureza de direito p\u00fablico e podem realizar atividades t\u00edpicas de Estado. Portanto, as autarquias podem atuar de forma semelhante \u00e0 Administra\u00e7\u00e3o centralizada, por\u00e9m com maior autonomia e especializa\u00e7\u00e3o, dada a sua pr\u00f3pria personalidade jur\u00eddica. Com efeito, anota-se\u00a0que \u00e9 comum chamar as autarquias de <strong>servi\u00e7o p\u00fablico personificado<\/strong>, justamente porque s\u00e3o criadas por meio da descentraliza\u00e7\u00e3o de um servi\u00e7o p\u00fablico espec\u00edfico, ao qual \u00e9 atribu\u00edda a personalidade jur\u00eddica pr\u00f3pria. Por exemplo: o INSS \u00e9 uma autarquia criada para realizar atividades relacionadas ao servi\u00e7o de previd\u00eancia social.<\/p>\n<p style=\"text-align: justify;\">Por outro lado, as funda\u00e7\u00f5es p\u00fablicas representam um <strong>patrim\u00f4nio personificado<\/strong>. Isso porque as funda\u00e7\u00f5es s\u00e3o criadas a partir de um patrim\u00f4nio, ao qual \u00e9 dada a personalidade jur\u00eddica espec\u00edfica. Por exemplo:\u00a0uma prefeitura poderia &#8220;pegar&#8221; um pr\u00e9dio e equipamentos de um hospital p\u00fablico e dar-lhe sua pr\u00f3pria personalidade jur\u00eddica, criando uma funda\u00e7\u00e3o p\u00fablica para gerir o hospital de forma descentralizada.<\/p>\n<p style=\"text-align: justify;\">Lembra-se ainda que as funda\u00e7\u00f5es podem\u00a0ter personalidade de direito p\u00fablico ou de direito privado. No primeiro caso, elas s\u00e3o, na verdade,\u00a0esp\u00e9cies de autarquias, ao ponto de serem chamadas de &#8220;autarquias fundacionais&#8221; ou &#8220;funda\u00e7\u00f5es aut\u00e1rquicas&#8221;.<\/p>\n<p style=\"text-align: justify;\">Por fim, as empresas p\u00fablicas e as sociedades de economia mista s\u00e3o criadas\u00a0para atuar na <strong>explora\u00e7\u00e3o de atividade econ\u00f4mica<\/strong> ou na <strong>presta\u00e7\u00e3o de servi\u00e7os p\u00fablicos<\/strong>, podendo atuar em um regime muito parecido com o aplicado na iniciativa privada. Lembra-se, ademais, que a Constitui\u00e7\u00e3o Federal disp\u00f5e que as empresas p\u00fablicas e sociedades de economia mista que atuarem na explora\u00e7\u00e3o de atividade econ\u00f4mica dever\u00e3o se sujeitar ao <strong>regime jur\u00eddico pr\u00f3prio das empresas privadas, inclusive quanto aos direitos e obriga\u00e7\u00f5es civis, comerciais, trabalhistas e tribut\u00e1rios.<\/strong><\/p>\n<p style=\"text-align: justify;\">Um ponto que aparece muito em prova trata das diferen\u00e7as entre as empresas p\u00fablicas e as sociedades de economia mista. Na verdade, tais entidades possuem muito mais semelhan\u00e7as do que diferen\u00e7as.<\/p>\n<p style=\"text-align: justify;\">Por\u00e9m, elas se diferenciam, basicamente, por <strong>dois<\/strong> pontos (veremos que, no \u00e2mbito federal, s\u00e3o tr\u00eas diferen\u00e7as):<\/p>\n<ol style=\"text-align: justify;\">\n<li style=\"text-align: justify;\">as empresas p\u00fablicas somente admitem capital p\u00fablico, ao passo que as sociedades de economia mista admitem a conjuga\u00e7\u00e3o de capital p\u00fablico e privado, desde que o ente instituidor mantenha a maioria do capital votante;<\/li>\n<li style=\"text-align: justify;\">as empresas p\u00fablicas podem ser constitu\u00eddas sob qualquer forma prevista em direito, enquanto as sociedades de economia mista admitem apenas a forma de sociedade an\u00f4nima (S.A.).<\/li>\n<\/ol>\n<p style=\"text-align: justify;\">Al\u00e9m disso, no \u00e2mbito federal, h\u00e1 uma terceira diferen\u00e7a. As empresas p\u00fablicas federais possuem foro na justi\u00e7a federal, ao passo que as sociedades de economia mista federais possuem foro na justi\u00e7a estadual. Essa \u00e9 a regra, que \u00e9 excepcionada por alguns casos espec\u00edficos, como as compet\u00eancias das justi\u00e7as especializadas (exemplo: causas trabalhistas dos empregados p\u00fablicos, das duas entidades, s\u00e3o resolvidas na justi\u00e7a do trabalho).<\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-56643 size-full\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2016\/12\/01181334\/empresa_p%C3%BAblica_sociedade_mista.jpg\" alt=\"administra\u00e7\u00e3o direta e indireta\" width=\"480\" height=\"480\" srcset=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2016\/12\/01181334\/empresa_p%C3%BAblica_sociedade_mista.jpg 480w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2016\/12\/01181334\/empresa_p%C3%BAblica_sociedade_mista.jpg 150w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2016\/12\/01181334\/empresa_p%C3%BAblica_sociedade_mista.jpg 300w\" sizes=\"auto, (max-width: 480px) 100vw, 480px\" \/><\/p>\n<p style=\"text-align: justify;\">\u00a0&#8212;-<\/p>\n<p style=\"text-align: justify;\">Bom, \u00e9 isso! Vimos bastante coisa, ent\u00e3o vamos resolver umas quest\u00f5es, para treinar um pouco!<\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-56644\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2016\/12\/01181448\/novas-corujas-11-34139.png\" alt=\"novas-corujas-11-34139\" width=\"314\" height=\"110\" \/><\/p>\n<p style=\"text-align: justify;\"><strong>1.\u00a0(FCC \u2013 T\u00e9cnico de N\u00edvel Superior\/Prefeitura de Teresina-PI\/2016) Pessoa jur\u00eddica de direito privado, constitu\u00edda sob a forma da legisla\u00e7\u00e3o brasileira, com parte do capital pertencente a entes p\u00fablicos, na condi\u00e7\u00e3o de detentores do controle, prestadora de servi\u00e7o p\u00fablico, sujeita a regime licitat\u00f3rio para contrata\u00e7\u00e3o das atividades meio, descreve uma<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>a) sociedade de economia mista.<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>b) autarquia.<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>c) funda\u00e7\u00e3o.<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>d) empresa p\u00fablica.<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>e) autarquia especial.<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong><u>Coment\u00e1rio<\/u><\/strong>: tanto as empresas p\u00fablicas como as sociedades de economia mista possuem personalidade de direito privado e podem explorar a presta\u00e7\u00e3o de servi\u00e7os p\u00fablicos. Contudo, segundo o enunciado, \u201c<em><u>parte<\/u><\/em> do capital pertence a entes p\u00fablicos\u201d, o que caracteriza a entidade como uma sociedade de economia mista, j\u00e1 que, nas empresas p\u00fablicas, <em><u>todo<\/u><\/em> o capital pertence a entes p\u00fablicos.<\/p>\n<p style=\"text-align: justify;\"><strong>Gabarito: alternativa A.<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>2. (Cespe \u2013 T\u00e9cnico Judici\u00e1rio\/TRT 8\u00aa Regi\u00e3o\/2016) A autarquia<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>a) \u00e9 pessoa jur\u00eddica de direito p\u00fablico.<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>b) inicia-se com a inscri\u00e7\u00e3o de seu ato constitutivo em registro p\u00fablico.<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>c) subordina-se ao ente estatal que a instituir.<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>d) \u00e9 uma entidade de compet\u00eancia pol\u00edtica, desprovida de car\u00e1ter administrativo.<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>e) integra a administra\u00e7\u00e3o p\u00fablica direta.<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong><u>Coment\u00e1rio<\/u><\/strong>: essa \u00e9 uma quest\u00e3o muito simples. A autarquia \u00e9 pessoa jur\u00eddica de direito p\u00fablico \u2013 letra A. Vamos analisar as outras op\u00e7\u00f5es:<\/p>\n<p style=\"text-align: justify;\">b) a autarquia inicia-se com a lei de sua cria\u00e7\u00e3o. A inscri\u00e7\u00e3o do ato constitutivo em registro p\u00fablico \u00e9 a marca da cria\u00e7\u00e3o das entidades de direito privado \u2013 ERRADA;<\/p>\n<p style=\"text-align: justify;\">c) n\u00e3o h\u00e1 subordina\u00e7\u00e3o entre a autarquia (ou qualquer outra entidade administrativa) e o ente estatal que a instituir \u2013 ERRADA;<\/p>\n<p style=\"text-align: justify;\">d) pelo contr\u00e1rio: a autarquia \u00e9 entidade de compet\u00eancia administrativa, desprovida de car\u00e1ter pol\u00edtico, isto \u00e9, n\u00e3o possui capacidade legislativa \u2013 ERRADA;<\/p>\n<p style=\"text-align: justify;\">e) a autarquia integra a administra\u00e7\u00e3o p\u00fablica <u>in<\/u>direta \u2013 ERRADA.<\/p>\n<p style=\"text-align: justify;\"><strong>Gabarito: alternativa A.<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>3. (Cespe \u2013 T\u00e9cnico Judici\u00e1rio\/TRE-PI\/2016)<\/strong> <strong>Entidade administrativa, com personalidade jur\u00eddica de direito p\u00fablico, destinada a supervisionar e fiscalizar o ensino superior, criada mediante lei espec\u00edfica,<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>a) \u00e9 regida, predominantemente, pelo regime jur\u00eddico de direito privado.<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>b) integra a administra\u00e7\u00e3o direta.<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>c) possui autonomia e \u00e9 titular de direitos e obriga\u00e7\u00f5es pr\u00f3prios.<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>d) tem natureza de empresa p\u00fablica.<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>e) \u00e9 exemplo de entidade resultante da desconcentra\u00e7\u00e3o administrativa.<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong><u>Coment\u00e1rio<\/u><\/strong>: as entidades administrativas s\u00e3o aquelas que comp\u00f5em a administra\u00e7\u00e3o indireta, ou seja, autarquias, funda\u00e7\u00f5es p\u00fablicas, empresas p\u00fablicas e sociedades de economia mista.<\/p>\n<p style=\"text-align: justify;\">As duas \u00faltimas possuem personalidade jur\u00eddica de direito privado, sendo criadas para a presta\u00e7\u00e3o de servi\u00e7os p\u00fablicos ou explora\u00e7\u00e3o de atividade econ\u00f4mica. Assim, o caso da quest\u00e3o n\u00e3o trata de nenhuma dessas entidades.<\/p>\n<p style=\"text-align: justify;\">As funda\u00e7\u00f5es p\u00fablicas, por outro lado, podem possuir tanto personalidade jur\u00eddica de direito p\u00fablico como de direito privado. Quando possuem personalidade de direito privado, a cria\u00e7\u00e3o \u00e9 autorizada por lei, ou seja, n\u00e3o s\u00e3o criadas diretamente mediante lei. Logo, o caso da quest\u00e3o n\u00e3o descreve uma funda\u00e7\u00e3o de direito privado.<\/p>\n<p style=\"text-align: justify;\">Assim, sobraram as autarquias e as funda\u00e7\u00f5es p\u00fablicas de direito p\u00fablico. Nos dois casos, o regime jur\u00eddico \u00e9 o mesmo, tanto que as funda\u00e7\u00f5es de direito p\u00fablico chegam a ser chamadas de funda\u00e7\u00f5es aut\u00e1rquicas ou autarquias fundacionais.<\/p>\n<p style=\"text-align: justify;\">Com efeito, as autarquias e as funda\u00e7\u00f5es aut\u00e1rquicas s\u00e3o criadas mediante lei e desempenham atividade t\u00edpica de Estado, incluindo a\u00ed a supervis\u00e3o e fiscaliza\u00e7\u00e3o do ensino superior.<\/p>\n<p style=\"text-align: justify;\">Agora, vamos analisar as alternativas:<\/p>\n<p style=\"text-align: justify;\">a) elas s\u00e3o regidas predominantemente pelo regime de direito p\u00fablico \u2013 ERRADA;<\/p>\n<p style=\"text-align: justify;\">b) as autarquias e funda\u00e7\u00f5es aut\u00e1rquicas integram a administra\u00e7\u00e3o <u>indireta<\/u> \u2013 ERRADA;<\/p>\n<p style=\"text-align: justify;\">c) as entidades administrativas, em geral, possuem autonomia e s\u00e3o titulares de direitos e obriga\u00e7\u00f5es, uma vez que possuem a sua pr\u00f3pria personalidade jur\u00eddica. Assim, esta \u00e9 a alternativa correta, uma vez que descreve uma caracter\u00edstica das entidades administrativas \u2013 CORRETA;<\/p>\n<p style=\"text-align: justify;\">d) a natureza da entidade \u00e9 de autarquia \u2013 ERRADA;<\/p>\n<p style=\"text-align: justify;\">e) a cria\u00e7\u00e3o de entidades administrativas decorre do fen\u00f4meno denominado <u>descentraliza\u00e7\u00e3o<\/u> Na desconcentra\u00e7\u00e3o, ocorre a cria\u00e7\u00e3o de \u00f3rg\u00e3os (n\u00e3o de entidades) \u2013 ERRADA.<\/p>\n<p style=\"text-align: justify;\"><strong>Gabarito: alternativa C.<\/strong><\/p>\n<p style=\"text-align: justify;\">&#8212;-<\/p>\n<p style=\"text-align: justify;\">\u00c9 isso, pessoal! Acredito que vimos os temas mais importantes sobre\u00a0a Administra\u00e7\u00e3o direta e indireta. Claro que o tema tem outros pontos importantes. Assim, se voc\u00ea ainda n\u00e3o conhece o nosso trabalho, convido-o para ler e assistir as aulas demonstrativas dos nossos cursos:<\/p>\n<p><a href=\"https:\/\/www.estrategiaconcursos.com.br\/cursosPorProfessor\/herbert-almeida-3314\/\" target=\"_blank\" rel=\"noopener\">Cursos do professor Herbert Almeida<\/a><\/p>\n<p>Confira, abaixo, os concursos que est\u00e3o abertos:<\/p>\n<blockquote class=\"wp-embedded-content\" data-secret=\"jAYfm9UIc7\"><p><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-abertos\/\">Concursos Abertos: milhares de vagas e inicial de R$ 22 mil!<\/a><\/p><\/blockquote>\n<p><iframe loading=\"lazy\" class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; clip: rect(1px, 1px, 1px, 1px);\" title=\"&#8220;Concursos Abertos: milhares de vagas e inicial de R$ 22 mil!&#8221; &#8212; Estrat\u00e9gia Concursos\" src=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-abertos\/embed\/#?secret=PejccyEH6u#?secret=jAYfm9UIc7\" data-secret=\"jAYfm9UIc7\" width=\"500\" height=\"282\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe><\/p>\n<p><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-previstos-2017\/\" target=\"_blank\" rel=\"noopener\">Concursos 2017<\/a><\/p>\n<p>Siga-nos tamb\u00e9m nas redes sociais e se inscreva na nossa lista especial para receber materiais gratuitos de Direito Administrativo:<\/p>\n<p style=\"text-align: justify;\">Lista especial:\u00a0<a href=\"http:\/\/eepurl.com\/caWVb5\" target=\"_blank\" rel=\"noopener\">http:\/\/eepurl.com\/caWVb5<\/a><\/p>\n<p style=\"text-align: justify;\">Facebook\u00a0<a href=\"https:\/\/www.facebook.com\/profherbertalmeida\" target=\"_blank\" rel=\"noopener\"><strong>\/profherbertalmeida<\/strong><\/a><\/p>\n<p style=\"text-align: justify;\">Instagram\u00a0<a href=\"https:\/\/www.instagram.com\/profherbertalmeida\/\" target=\"_blank\" rel=\"noopener\">@<strong>profherbertalmeida<\/strong><\/a><\/p>\n<p style=\"text-align: justify;\">Youtube <a href=\"https:\/\/www.youtube.com\/profherbertalmeida\" target=\"_blank\" rel=\"noopener\"><strong>\/profherbertalmeida<\/strong><\/a><\/p>\n<p style=\"text-align: justify;\">Uma grande abra\u00e7o a todos!<\/p>\n<p style=\"text-align: justify;\">Prof. Herbert Almeida<\/p>\n<p>Confira a lista de <a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-2021\/\" target=\"_blank\" rel=\"noreferrer noopener\">concursos 2021<\/a>: Veja os principais <a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-abertos\/\" target=\"_blank\" rel=\"noreferrer noopener\">concursos abertos<\/a> com altos sal\u00e1rios que oferecem oportunidades para todos os n\u00edveis de escolaridade!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Diferen\u00e7a entre Administra\u00e7\u00e3o direta e indireta &#8211; Dica Estrat\u00e9gica &#8211; Direito Adminitrativo Ol\u00e1 amigos, tudo bem? Aqui \u00e9 o Prof. Herbert Almeida. Hoje, vamos iniciar a nossa participa\u00e7\u00e3o no projeto de Dicas Estrat\u00e9gicas do Estrat\u00e9gia Concursos. O assunto que vamos falar\u00a0n\u00e3o \u00e9 t\u00e3o complicado, mas aparece MUITO em provas de concursos p\u00fablicos, de todas as [&hellip;]<\/p>\n","protected":false},"author":129,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"post_tipo":"article","footnotes":""},"categories":[1],"tags":[],"tax_estado":[],"class_list":["post-56597","post","type-post","status-publish","format-standard","hentry","category-cursos-e-concursos"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.2 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>O que \u00e9 Administra\u00e7\u00e3o Direta e Indireta? | Estrat\u00e9gia Concursos<\/title>\n<meta name=\"description\" content=\"Qual a diferen\u00e7a entre Administra\u00e7\u00e3o Direta e Indireta? O professor de Direito Administrativo, Herbert Almeida, explica nessa Dica Estrat\u00e9gica. Confira!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/administracao-direta-e-indireta\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Administra\u00e7\u00e3o direta e indireta - Dica Estrat\u00e9gica - Direito Adminitrativo\" \/>\n<meta property=\"og:description\" content=\"Qual a diferen\u00e7a entre Administra\u00e7\u00e3o Direta e Indireta? O professor de Direito Administrativo, Herbert Almeida, explica nessa Dica Estrat\u00e9gica. Confira!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/administracao-direta-e-indireta\/\" \/>\n<meta property=\"og:site_name\" content=\"Estrat\u00e9gia Concursos\" \/>\n<meta property=\"article:published_time\" content=\"2016-12-02T20:52:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-02-24T15:00:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-content\/uploads\/2016\/11\/dicas-estrategicas-2-06-1-300x122.png\" \/>\n<meta name=\"author\" content=\"Herbert Almeida\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:site\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Herbert Almeida\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"15 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/administracao-direta-e-indireta\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/administracao-direta-e-indireta\/\"},\"author\":{\"name\":\"Herbert Almeida\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/59717c75350fa01aa0fd68a52a8d02e0\"},\"headline\":\"Administra\u00e7\u00e3o direta e indireta &#8211; Dica Estrat\u00e9gica &#8211; Direito Adminitrativo\",\"datePublished\":\"2016-12-02T20:52:00+00:00\",\"dateModified\":\"2021-02-24T15:00:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/administracao-direta-e-indireta\/\"},\"wordCount\":2918,\"commentCount\":51,\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/administracao-direta-e-indireta\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-content\/uploads\/2016\/11\/dicas-estrategicas-2-06-1-300x122.png\",\"articleSection\":[\"Concursos P\u00fablicos\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/administracao-direta-e-indireta\/#respond\"]}],\"copyrightYear\":\"2016\",\"copyrightHolder\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/administracao-direta-e-indireta\/\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/administracao-direta-e-indireta\/\",\"name\":\"O que \u00e9 Administra\u00e7\u00e3o Direta e Indireta? | Estrat\u00e9gia Concursos\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/administracao-direta-e-indireta\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/administracao-direta-e-indireta\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-content\/uploads\/2016\/11\/dicas-estrategicas-2-06-1-300x122.png\",\"datePublished\":\"2016-12-02T20:52:00+00:00\",\"dateModified\":\"2021-02-24T15:00:32+00:00\",\"description\":\"Qual a diferen\u00e7a entre Administra\u00e7\u00e3o Direta e Indireta? O professor de Direito Administrativo, Herbert Almeida, explica nessa Dica Estrat\u00e9gica. Confira!\",\"breadcrumb\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/administracao-direta-e-indireta\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/administracao-direta-e-indireta\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/administracao-direta-e-indireta\/#primaryimage\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-content\/uploads\/2016\/11\/dicas-estrategicas-2-06-1-300x122.png\",\"contentUrl\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-content\/uploads\/2016\/11\/dicas-estrategicas-2-06-1-300x122.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/administracao-direta-e-indireta\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Administra\u00e7\u00e3o direta e indireta &#8211; Dica Estrat\u00e9gica &#8211; Direito Adminitrativo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"name\":\"Estrat\u00e9gia Concursos\",\"description\":\"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.\",\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\",\"name\":\"Estrat\u00e9gia Concursos\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"width\":230,\"height\":60,\"caption\":\"Estrat\u00e9gia Concursos\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/EstratConcursos\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/59717c75350fa01aa0fd68a52a8d02e0\",\"name\":\"Herbert Almeida\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/b6461a43893c24d5fc91efc433971ffec025c84c0341129f4578034d77f9a536?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/b6461a43893c24d5fc91efc433971ffec025c84c0341129f4578034d77f9a536?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/b6461a43893c24d5fc91efc433971ffec025c84c0341129f4578034d77f9a536?s=96&d=mm&r=g\",\"caption\":\"Herbert Almeida\"},\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/herbertestrategiaconcursos-com-br\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"O que \u00e9 Administra\u00e7\u00e3o Direta e Indireta? | Estrat\u00e9gia Concursos","description":"Qual a diferen\u00e7a entre Administra\u00e7\u00e3o Direta e Indireta? O professor de Direito Administrativo, Herbert Almeida, explica nessa Dica Estrat\u00e9gica. Confira!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.estrategiaconcursos.com.br\/blog\/administracao-direta-e-indireta\/","og_locale":"pt_BR","og_type":"article","og_title":"Administra\u00e7\u00e3o direta e indireta - Dica Estrat\u00e9gica - Direito Adminitrativo","og_description":"Qual a diferen\u00e7a entre Administra\u00e7\u00e3o Direta e Indireta? O professor de Direito Administrativo, Herbert Almeida, explica nessa Dica Estrat\u00e9gica. Confira!","og_url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/administracao-direta-e-indireta\/","og_site_name":"Estrat\u00e9gia Concursos","article_published_time":"2016-12-02T20:52:00+00:00","article_modified_time":"2021-02-24T15:00:32+00:00","og_image":[{"url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-content\/uploads\/2016\/11\/dicas-estrategicas-2-06-1-300x122.png","type":"","width":"","height":""}],"author":"Herbert Almeida","twitter_card":"summary_large_image","twitter_creator":"@EstratConcursos","twitter_site":"@EstratConcursos","twitter_misc":{"Escrito por":"Herbert Almeida","Est. tempo de leitura":"15 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/administracao-direta-e-indireta\/#article","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/administracao-direta-e-indireta\/"},"author":{"name":"Herbert Almeida","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/59717c75350fa01aa0fd68a52a8d02e0"},"headline":"Administra\u00e7\u00e3o direta e indireta &#8211; Dica Estrat\u00e9gica &#8211; Direito Adminitrativo","datePublished":"2016-12-02T20:52:00+00:00","dateModified":"2021-02-24T15:00:32+00:00","mainEntityOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/administracao-direta-e-indireta\/"},"wordCount":2918,"commentCount":51,"publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/administracao-direta-e-indireta\/#primaryimage"},"thumbnailUrl":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-content\/uploads\/2016\/11\/dicas-estrategicas-2-06-1-300x122.png","articleSection":["Concursos P\u00fablicos"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/administracao-direta-e-indireta\/#respond"]}],"copyrightYear":"2016","copyrightHolder":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/administracao-direta-e-indireta\/","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/administracao-direta-e-indireta\/","name":"O que \u00e9 Administra\u00e7\u00e3o Direta e Indireta? | Estrat\u00e9gia Concursos","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/administracao-direta-e-indireta\/#primaryimage"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/administracao-direta-e-indireta\/#primaryimage"},"thumbnailUrl":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-content\/uploads\/2016\/11\/dicas-estrategicas-2-06-1-300x122.png","datePublished":"2016-12-02T20:52:00+00:00","dateModified":"2021-02-24T15:00:32+00:00","description":"Qual a diferen\u00e7a entre Administra\u00e7\u00e3o Direta e Indireta? O professor de Direito Administrativo, Herbert Almeida, explica nessa Dica Estrat\u00e9gica. Confira!","breadcrumb":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/administracao-direta-e-indireta\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/administracao-direta-e-indireta\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/administracao-direta-e-indireta\/#primaryimage","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-content\/uploads\/2016\/11\/dicas-estrategicas-2-06-1-300x122.png","contentUrl":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-content\/uploads\/2016\/11\/dicas-estrategicas-2-06-1-300x122.png"},{"@type":"BreadcrumbList","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/administracao-direta-e-indireta\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.estrategiaconcursos.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Administra\u00e7\u00e3o direta e indireta &#8211; Dica Estrat\u00e9gica &#8211; Direito Adminitrativo"}]},{"@type":"WebSite","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","name":"Estrat\u00e9gia Concursos","description":"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.","publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization","name":"Estrat\u00e9gia Concursos","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","width":230,"height":60,"caption":"Estrat\u00e9gia Concursos"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/EstratConcursos"]},{"@type":"Person","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/59717c75350fa01aa0fd68a52a8d02e0","name":"Herbert Almeida","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/b6461a43893c24d5fc91efc433971ffec025c84c0341129f4578034d77f9a536?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b6461a43893c24d5fc91efc433971ffec025c84c0341129f4578034d77f9a536?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b6461a43893c24d5fc91efc433971ffec025c84c0341129f4578034d77f9a536?s=96&d=mm&r=g","caption":"Herbert Almeida"},"url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/herbertestrategiaconcursos-com-br\/"}]}},"_links":{"self":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/56597","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/users\/129"}],"replies":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/comments?post=56597"}],"version-history":[{"count":9,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/56597\/revisions"}],"predecessor-version":[{"id":679259,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/56597\/revisions\/679259"}],"wp:attachment":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media?parent=56597"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/categories?post=56597"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tags?post=56597"},{"taxonomy":"tax_estado","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tax_estado?post=56597"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}