{"id":544951,"date":"2020-07-21T15:43:52","date_gmt":"2020-07-21T18:43:52","guid":{"rendered":"https:\/\/blog-estrategia.mystagingwebsite.com\/blog\/?p=544951"},"modified":"2020-10-02T13:32:25","modified_gmt":"2020-10-02T16:32:25","slug":"pesquisa-carreiras-publicas","status":"publish","type":"post","link":"https:\/\/www.estrategiaconcursos.com.br\/blog\/pesquisa-carreiras-publicas\/","title":{"rendered":"Pesquisa aponta carreiras p\u00fablicas de elite como as mais rent\u00e1veis"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Um levantamento produzido pelo portal G1, com base nos dados disponibilizados pela Receita Federal do Brasil, constatou que as carreiras mais bem remuneradas do pa\u00eds s\u00e3o do setor p\u00fablico.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A pesquisa se baseou no relat\u00f3rio &#8216;<a rel=\"noreferrer noopener\" href=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/07\/21135535\/grandes-numeros-irpf-2018-2019-completo.pdf\" target=\"_blank\">Grandes N\u00fameros das Declara\u00e7\u00f5es do Imposto de Renda das Pessoas F\u00edsicas<\/a>&#8216;, da Receita Federal, que utilizou as 30,2 milh\u00f5es de declara\u00e7\u00f5es de imposto de renda recebidas em 2019 para comparar o rendimento dos cidad\u00e3os, com base em 135 principais carreiras p\u00fablicas ou privadas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De acordo com a pesquisa, considerando todos os declarantes, o rendimento mensal m\u00e9dio foi de <strong>R$ 8.528,00<\/strong>, sendo que das 135 principais carreiras avaliadas, <strong>76<\/strong> apresentaram rendimento abaixo da m\u00e9dia e <strong>59<\/strong> acima. O n\u00famero, no entanto, acaba sendo influenciado pela alta remunera\u00e7\u00e3o das 59 carreiras acima da m\u00e9dia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Os n\u00fameros do relat\u00f3rio apresentam, ainda, as carreiras com as maiores e menores parcelas de renda isenta de imposto de renda. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Um produtor agropecu\u00e1rio, por exemplo, tem at\u00e9 66,79% de seus rendimentos isentos de IR. Professores e policiais, por sua vez, t\u00eam, respectivamente, apenas 6,61% e 7,80% de rendimentos isentos. <\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Top 5 &#8211; Carreiras mais rent\u00e1veis<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">A pesquisa refor\u00e7a que, quando o assunto \u00e9 rentabilidade, as carreiras p\u00fablicas de elite continuam no topo. Confira o ranking que comparou as 135 principais carreiras: <\/p>\n\n\n\n<figure class=\"wp-block-table is-style-stripes\"><table><tbody><tr><td class=\"has-text-align-center\" data-align=\"center\"><strong>Cargo<\/strong><\/td><td class=\"has-text-align-center\" data-align=\"center\"><strong>Renda m\u00e9dia mensal<\/strong><\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">Titular de Cart\u00f3rio<\/td><td class=\"has-text-align-center\" data-align=\"center\">R$ 103.141,14<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">Membro do Minist\u00e9rio P\u00fablico<\/td><td class=\"has-text-align-center\" data-align=\"center\"> R$ 53.493,48<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">Membro do Poder Judici\u00e1rio e de Tribunal de Contas<\/td><td class=\"has-text-align-center\" data-align=\"center\">R$ 51.773,10<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">Diplomata e afins<\/td><td class=\"has-text-align-center\" data-align=\"center\">R$ 39.571,66<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">Advogado do setor p\u00fablico e consultor jur\u00eddico<\/td><td class=\"has-text-align-center\" data-align=\"center\">R$ 30.884,91<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Como visto acima, das 135 carreiras mais rent\u00e1veis, as <strong>cinco primeiras<\/strong> s\u00e3o p\u00fablicas de elite, com altas remunera\u00e7\u00f5es. Se focarmos apenas nas carreiras p\u00fablicas, outras oportunidades tamb\u00e9m figuram entre as mais rent\u00e1veis, como os servidores de carreira do Bacen, CVM e Susep, das carreiras de auditoria fiscal e das carreiras dos Poderes Judici\u00e1rio e Legislativo e Executivo. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">As profiss\u00f5es com o menor rendimento m\u00e9dio mensal ainda s\u00e3o as consideradas como servi\u00e7os bra\u00e7ais, prestadores de servi\u00e7o ou ligadas \u00e0 ind\u00fastria.  <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Agora que voc\u00ea constatou que as carreiras p\u00fablicas s\u00e3o op\u00e7\u00f5es extremamente vantajosas para quem busca remunera\u00e7\u00e3o acima da m\u00e9dia nacional e estabilidade, que tal ficar por dentro de todas as oportunidades abertas ou previstas?  <\/p>\n\n\n\n<p class=\"has-text-align-center has-medium-font-size wp-block-paragraph\"><em><strong>Fique por dentro de todos os concursos<\/strong><\/em>:<\/p>\n\n\n\n<p class=\"has-text-align-center has-pale-cyan-blue-background-color has-background wp-block-paragraph\" style=\"font-size:clamp(15.747px, 0.984rem + ((1vw - 3.2px) * 0.809), 24px);px\"><strong><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-abertos\/\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\"Concursos abertos (abre numa nova aba)\">Concursos abertos<\/a><\/strong><\/p>\n\n\n\n<p class=\"has-text-align-center has-pale-cyan-blue-background-color has-background wp-block-paragraph\" style=\"font-size:clamp(15.197px, 0.95rem + ((1vw - 3.2px) * 0.765), 23px);px\"><a rel=\"noreferrer noopener\" aria-label=\"Concursos 2020 (abre numa nova aba)\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-2020\/\" target=\"_blank\"><strong>Concursos 2020<\/strong><\/a><\/p>\n\n\n\n<p class=\"has-text-align-center has-pale-cyan-blue-background-color has-background wp-block-paragraph\" style=\"font-size:clamp(15.197px, 0.95rem + ((1vw - 3.2px) * 0.765), 23px);px\"><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-2021\/\"><strong>Concursos 2021<\/strong><\/a><\/p>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\"><em><strong>Assinatura Anual Ilimitada*<\/strong><\/em><\/p>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\"><em>Prepare-se com o melhor material e com quem mais aprova em Concursos P\u00fablicos em todo o pa\u00eds. Assine agora a nossa Assinatura Anual e tenha acesso ilimitado* a todos os nossos cursos.<\/em><\/p>\n\n\n\n<p class=\"has-text-align-center has-luminous-vivid-amber-background-color has-background wp-block-paragraph\" style=\"font-size:clamp(14.642px, 0.915rem + ((1vw - 3.2px) * 0.721), 22px);px\"><strong>ASSINE AGORA<\/strong>&nbsp;\u2013&nbsp;<a rel=\"noreferrer noopener\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/assinaturas\/\" target=\"_blank\"><strong>Assinatura Ilimitada<\/strong><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Um levantamento produzido pelo portal G1, com base nos dados disponibilizados pela Receita Federal do Brasil, constatou que as carreiras mais bem remuneradas do pa\u00eds s\u00e3o do setor p\u00fablico. A pesquisa se baseou no relat\u00f3rio &#8216;Grandes N\u00fameros das Declara\u00e7\u00f5es do Imposto de Renda das Pessoas F\u00edsicas&#8216;, da Receita Federal, que utilizou as 30,2 milh\u00f5es de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":399557,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"post_tipo":"news","footnotes":""},"categories":[1],"tags":[],"tax_estado":[],"class_list":["post-544951","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cursos-e-concursos"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Pesquisa aponta carreiras p\u00fablicas de elite como as mais rent\u00e1veis<\/title>\n<meta name=\"description\" content=\"As carreiras p\u00fablicas de elite continuam a figurar entre as mais rent\u00e1veis de todo o pa\u00eds. Confira mais dados deste levantamento.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/pesquisa-carreiras-publicas\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pesquisa aponta carreiras p\u00fablicas de elite como as mais rent\u00e1veis\" \/>\n<meta property=\"og:description\" content=\"As carreiras p\u00fablicas de elite continuam a figurar entre as mais rent\u00e1veis de todo o pa\u00eds. Confira mais dados deste levantamento.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/pesquisa-carreiras-publicas\/\" \/>\n<meta property=\"og:site_name\" content=\"Estrat\u00e9gia Concursos\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/EstrategiaConcursos\" \/>\n<meta property=\"article:published_time\" content=\"2020-07-21T18:43:52+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-10-02T16:32:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2019\/07\/17001940\/logo-estrategia-concursos1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"576\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Coordena\u00e7\u00e3o\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:site\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Coordena\u00e7\u00e3o\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/pesquisa-carreiras-publicas\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/pesquisa-carreiras-publicas\\\/\"},\"author\":{\"name\":\"Coordena\u00e7\u00e3o\",\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/#\\\/schema\\\/person\\\/b4a388c97673c5f483d72185668afa1f\"},\"headline\":\"Pesquisa aponta carreiras p\u00fablicas de elite como as mais rent\u00e1veis\",\"datePublished\":\"2020-07-21T18:43:52+00:00\",\"dateModified\":\"2020-10-02T16:32:25+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/pesquisa-carreiras-publicas\\\/\"},\"wordCount\":457,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/pesquisa-carreiras-publicas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dhg1h5j42swfq.cloudfront.net\\\/2019\\\/07\\\/17001940\\\/logo-estrategia-concursos1.jpg\",\"articleSection\":[\"Concursos P\u00fablicos\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/pesquisa-carreiras-publicas\\\/#respond\"]}],\"copyrightYear\":\"2020\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/pesquisa-carreiras-publicas\\\/\",\"url\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/pesquisa-carreiras-publicas\\\/\",\"name\":\"Pesquisa aponta carreiras p\u00fablicas de elite como as mais rent\u00e1veis\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/pesquisa-carreiras-publicas\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/pesquisa-carreiras-publicas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dhg1h5j42swfq.cloudfront.net\\\/2019\\\/07\\\/17001940\\\/logo-estrategia-concursos1.jpg\",\"datePublished\":\"2020-07-21T18:43:52+00:00\",\"dateModified\":\"2020-10-02T16:32:25+00:00\",\"description\":\"As carreiras p\u00fablicas de elite continuam a figurar entre as mais rent\u00e1veis de todo o pa\u00eds. Confira mais dados deste levantamento.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/pesquisa-carreiras-publicas\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/pesquisa-carreiras-publicas\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/pesquisa-carreiras-publicas\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dhg1h5j42swfq.cloudfront.net\\\/2019\\\/07\\\/17001940\\\/logo-estrategia-concursos1.jpg\",\"contentUrl\":\"https:\\\/\\\/dhg1h5j42swfq.cloudfront.net\\\/2019\\\/07\\\/17001940\\\/logo-estrategia-concursos1.jpg\",\"width\":1024,\"height\":576},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/pesquisa-carreiras-publicas\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pesquisa aponta carreiras p\u00fablicas de elite como as mais rent\u00e1veis\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/\",\"name\":\"Estrat\u00e9gia Concursos\",\"description\":\"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/#organization\",\"name\":\"Estrat\u00e9gia Concursos\",\"url\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dhg1h5j42swfq.cloudfront.net\\\/2025\\\/06\\\/03203428\\\/logo_concursos-1.jpg\",\"contentUrl\":\"https:\\\/\\\/dhg1h5j42swfq.cloudfront.net\\\/2025\\\/06\\\/03203428\\\/logo_concursos-1.jpg\",\"width\":230,\"height\":60,\"caption\":\"Estrat\u00e9gia Concursos\"},\"image\":{\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/EstratConcursos\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/#\\\/schema\\\/person\\\/b4a388c97673c5f483d72185668afa1f\",\"name\":\"Coordena\u00e7\u00e3o\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b720319e4c9a967eb58678d110f4fe35452fc5d5f97b202bac7b8acceb18c6ad?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b720319e4c9a967eb58678d110f4fe35452fc5d5f97b202bac7b8acceb18c6ad?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b720319e4c9a967eb58678d110f4fe35452fc5d5f97b202bac7b8acceb18c6ad?s=96&d=mm&r=g\",\"caption\":\"Coordena\u00e7\u00e3o\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/EstrategiaConcursos\",\"https:\\\/\\\/x.com\\\/EstratConcursos\"],\"url\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/author\\\/estrategia2013\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Pesquisa aponta carreiras p\u00fablicas de elite como as mais rent\u00e1veis","description":"As carreiras p\u00fablicas de elite continuam a figurar entre as mais rent\u00e1veis de todo o pa\u00eds. Confira mais dados deste levantamento.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.estrategiaconcursos.com.br\/blog\/pesquisa-carreiras-publicas\/","og_locale":"pt_BR","og_type":"article","og_title":"Pesquisa aponta carreiras p\u00fablicas de elite como as mais rent\u00e1veis","og_description":"As carreiras p\u00fablicas de elite continuam a figurar entre as mais rent\u00e1veis de todo o pa\u00eds. Confira mais dados deste levantamento.","og_url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/pesquisa-carreiras-publicas\/","og_site_name":"Estrat\u00e9gia Concursos","article_author":"https:\/\/www.facebook.com\/EstrategiaConcursos","article_published_time":"2020-07-21T18:43:52+00:00","article_modified_time":"2020-10-02T16:32:25+00:00","og_image":[{"width":1024,"height":576,"url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2019\/07\/17001940\/logo-estrategia-concursos1.jpg","type":"image\/jpeg"}],"author":"Coordena\u00e7\u00e3o","twitter_card":"summary_large_image","twitter_creator":"@EstratConcursos","twitter_site":"@EstratConcursos","twitter_misc":{"Escrito por":"Coordena\u00e7\u00e3o","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/pesquisa-carreiras-publicas\/#article","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/pesquisa-carreiras-publicas\/"},"author":{"name":"Coordena\u00e7\u00e3o","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/b4a388c97673c5f483d72185668afa1f"},"headline":"Pesquisa aponta carreiras p\u00fablicas de elite como as mais rent\u00e1veis","datePublished":"2020-07-21T18:43:52+00:00","dateModified":"2020-10-02T16:32:25+00:00","mainEntityOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/pesquisa-carreiras-publicas\/"},"wordCount":457,"commentCount":0,"publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/pesquisa-carreiras-publicas\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2019\/07\/17001940\/logo-estrategia-concursos1.jpg","articleSection":["Concursos P\u00fablicos"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/pesquisa-carreiras-publicas\/#respond"]}],"copyrightYear":"2020","copyrightHolder":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/pesquisa-carreiras-publicas\/","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/pesquisa-carreiras-publicas\/","name":"Pesquisa aponta carreiras p\u00fablicas de elite como as mais rent\u00e1veis","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/pesquisa-carreiras-publicas\/#primaryimage"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/pesquisa-carreiras-publicas\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2019\/07\/17001940\/logo-estrategia-concursos1.jpg","datePublished":"2020-07-21T18:43:52+00:00","dateModified":"2020-10-02T16:32:25+00:00","description":"As carreiras p\u00fablicas de elite continuam a figurar entre as mais rent\u00e1veis de todo o pa\u00eds. Confira mais dados deste levantamento.","breadcrumb":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/pesquisa-carreiras-publicas\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/pesquisa-carreiras-publicas\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/pesquisa-carreiras-publicas\/#primaryimage","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2019\/07\/17001940\/logo-estrategia-concursos1.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2019\/07\/17001940\/logo-estrategia-concursos1.jpg","width":1024,"height":576},{"@type":"BreadcrumbList","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/pesquisa-carreiras-publicas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.estrategiaconcursos.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Pesquisa aponta carreiras p\u00fablicas de elite como as mais rent\u00e1veis"}]},{"@type":"WebSite","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","name":"Estrat\u00e9gia Concursos","description":"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.","publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization","name":"Estrat\u00e9gia Concursos","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","width":230,"height":60,"caption":"Estrat\u00e9gia Concursos"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/EstratConcursos"]},{"@type":"Person","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/b4a388c97673c5f483d72185668afa1f","name":"Coordena\u00e7\u00e3o","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/b720319e4c9a967eb58678d110f4fe35452fc5d5f97b202bac7b8acceb18c6ad?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b720319e4c9a967eb58678d110f4fe35452fc5d5f97b202bac7b8acceb18c6ad?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b720319e4c9a967eb58678d110f4fe35452fc5d5f97b202bac7b8acceb18c6ad?s=96&d=mm&r=g","caption":"Coordena\u00e7\u00e3o"},"sameAs":["https:\/\/www.facebook.com\/EstrategiaConcursos","https:\/\/x.com\/EstratConcursos"],"url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/estrategia2013\/"}]}},"_links":{"self":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/544951","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/comments?post=544951"}],"version-history":[{"count":0,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/544951\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media\/399557"}],"wp:attachment":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media?parent=544951"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/categories?post=544951"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tags?post=544951"},{"taxonomy":"tax_estado","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tax_estado?post=544951"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}