{"id":538575,"date":"2020-07-06T23:17:20","date_gmt":"2020-07-07T02:17:20","guid":{"rendered":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?p=538575"},"modified":"2020-07-06T23:17:22","modified_gmt":"2020-07-07T02:17:22","slug":"informativo-stj-669-comentado","status":"publish","type":"post","link":"https:\/\/www.estrategiaconcursos.com.br\/blog\/informativo-stj-669-comentado\/","title":{"rendered":"Informativo STJ 669 Comentado"},"content":{"rendered":"\n<p>Para n\u00e3o deixar passar nada, estamos colocando em dia os informativos de 2020 (todos eles!). E aqui vai o informativo 669 do STJ Comentad\u00edssimo.<\/p>\n\n\n\n<h2 class=\"has-text-align-center wp-block-heading\"><strong><a href=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/07\/06231642\/STJ-669.pdf\">DOWNLOAD do PDF AQUI!<\/a><\/strong><\/h2>\n\n\n<figure class=\"wp-block-embed-youtube wp-block-embed is-type-video is-provider-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"lyte-wrapper\" style=\"width:853px;max-width:100%;margin:5px;\"><div class=\"lyMe\" id=\"WYL_gcYPT4r1PWE\"><div id=\"lyte_gcYPT4r1PWE\" data-src=\"\/\/i.ytimg.com\/vi\/gcYPT4r1PWE\/hqdefault.jpg\" class=\"pL\"><div class=\"tC\"><div class=\"tT\"><\/div><\/div><div class=\"play\"><\/div><div class=\"ctrl\"><div class=\"Lctrl\"><\/div><div class=\"Rctrl\"><\/div><\/div><\/div><noscript><a href=\"https:\/\/youtu.be\/gcYPT4r1PWE\" rel=\"nofollow\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i.ytimg.com\/vi\/gcYPT4r1PWE\/0.jpg\" alt=\"YouTube video thumbnail\" width=\"853\" height=\"460\" \/><br \/>Assista a este v\u00eddeo no YouTube<\/a><\/noscript><\/div><\/div><div class=\"lL\" style=\"max-width:100%;width:853px;margin:5px;\"><\/div><figcaption><\/figcaption><\/figure>\n\n\n<p><a href=\"#_Toc44840483\">DIREITO CONSTITUCIONAL. 2<\/a><\/p>\n\n\n\n<p><a href=\"#_Toc44840484\">1.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Reclama\u00e7\u00e3o para controle de aplica\u00e7\u00e3o de entendimento firmado pelo STJ. 2<\/a><\/p>\n\n\n\n<p><a href=\"#_Toc44840485\">1.1.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Situa\u00e7\u00e3o F\u00c1TICA. 2<\/a><\/p>\n\n\n\n<p><a href=\"#_Toc44840486\">1.2.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; An\u00e1lise ESTRAT\u00c9GICA. 3<\/a><\/p>\n\n\n\n<p><a href=\"#_Toc44840487\">DIREITO ADMINISTRATIVO&#8230; 5<\/a><\/p>\n\n\n\n<p><a href=\"#_Toc44840488\">2.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Exame de sufici\u00eancia para t\u00e9cnicos em contabilidade formados antes da Lei n. 12.249\/10. 5<\/a><\/p>\n\n\n\n<p><a href=\"#_Toc44840489\">2.1.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Situa\u00e7\u00e3o F\u00c1TICA. 5<\/a><\/p>\n\n\n\n<p><a href=\"#_Toc44840490\">2.2.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; An\u00e1lise ESTRAT\u00c9GICA. 5<\/a><\/p>\n\n\n\n<p><a href=\"#_Toc44840491\">3.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Fixa\u00e7\u00e3o de cau\u00e7\u00e3o em valor diverso do previsto na lei de licita\u00e7\u00f5es. 6<\/a><\/p>\n\n\n\n<p><a href=\"#_Toc44840492\">3.1.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Situa\u00e7\u00e3o F\u00c1TICA. 6<\/a><\/p>\n\n\n\n<p><a href=\"#_Toc44840493\">3.2.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; An\u00e1lise ESTRAT\u00c9GICA. 7<\/a><\/p>\n\n\n\n<p><a href=\"#_Toc44840494\">DIREITO CIVIL. 8<\/a><\/p>\n\n\n\n<p><a href=\"#_Toc44840495\">4.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Legalidade da imputa\u00e7\u00e3o ao pagamento primeiramente nos juros. 8<\/a><\/p>\n\n\n\n<p><a href=\"#_Toc44840496\">4.1.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Situa\u00e7\u00e3o F\u00c1TICA. 8<\/a><\/p>\n\n\n\n<p><a href=\"#_Toc44840497\">4.2.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; An\u00e1lise ESTRAT\u00c9GICA. 8<\/a><\/p>\n\n\n\n<p><a href=\"#_Toc44840498\">5.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Circunst\u00e2ncias permissivas para a desonera\u00e7\u00e3o de alimentos fixados entre ex-c\u00f4njuges. 9<\/a><\/p>\n\n\n\n<p><a href=\"#_Toc44840499\">5.1.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Situa\u00e7\u00e3o F\u00c1TICA. 9<\/a><\/p>\n\n\n\n<p><a href=\"#_Toc44840500\">5.2.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; An\u00e1lise ESTRAT\u00c9GICA. 10<\/a><\/p>\n\n\n\n<p><a href=\"#_Toc44840501\">DIREITO PROCESSUAL CIVIL. 11<\/a><\/p>\n\n\n\n<p><a href=\"#_Toc44840502\">6.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Ponto facultativo baseado em ato do Executivo estadual e tempestividade recursal 11<\/a><\/p>\n\n\n\n<p><a href=\"#_Toc44840503\">6.1.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Situa\u00e7\u00e3o F\u00c1TICA. 11<\/a><\/p>\n\n\n\n<p><a href=\"#_Toc44840504\">6.2.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; An\u00e1lise ESTRAT\u00c9GICA. 12<\/a><\/p>\n\n\n\n<p><a href=\"#_Toc44840505\">7.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Acolhimento de impugna\u00e7\u00e3o ao valor da causa em momento posterior \u00e0 an\u00e1lise m\u00e9rito.. 13<\/a><\/p>\n\n\n\n<p><a href=\"#_Toc44840506\">7.1.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Situa\u00e7\u00e3o F\u00c1TICA. 13<\/a><\/p>\n\n\n\n<p><a href=\"#_Toc44840507\">7.2.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; An\u00e1lise ESTRAT\u00c9GICA. 14<\/a><\/p>\n\n\n\n<p><a href=\"#_Toc44840508\">DIREITO EMPRESARIAL. 14<\/a><\/p>\n\n\n\n<p><a href=\"#_Toc44840509\">8.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Sujei\u00e7\u00e3o dos honor\u00e1rios sucumbenciais ao ju\u00edzo recuperacional 14<\/a><\/p>\n\n\n\n<p><a href=\"#_Toc44840510\">8.1.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Situa\u00e7\u00e3o F\u00c1TICA. 15<\/a><\/p>\n\n\n\n<p><a href=\"#_Toc44840511\">8.2.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; An\u00e1lise ESTRAT\u00c9GICA. 15<\/a><\/p>\n\n\n\n<p><a href=\"#_Toc44840512\">DIREITO TRIBUT\u00c1RIO&#8230; 17<\/a><\/p>\n\n\n\n<p><a href=\"#_Toc44840513\">9.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Cr\u00e9dito presumido PIS\/PASEP e Cofins para cerealistas. 17<\/a><\/p>\n\n\n\n<p><a href=\"#_Toc44840514\">9.1.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Situa\u00e7\u00e3o F\u00c1TICA. 17<\/a><\/p>\n\n\n\n<p><a href=\"#_Toc44840515\">9.2.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; An\u00e1lise ESTRAT\u00c9GICA. 18<\/a><\/p>\n\n\n\n<p><a href=\"#_Toc44840516\">DIREITO PENAL. 19<\/a><\/p>\n\n\n\n<p><a href=\"#_Toc44840517\">10.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Cabimento de Habeas Corpus para retificar registros pret\u00e9ritos. 19<\/a><\/p>\n\n\n\n<p><a href=\"#_Toc44840518\">10.1.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Situa\u00e7\u00e3o F\u00e1tica. 19<\/a><\/p>\n\n\n\n<p><a href=\"#_Toc44840519\">10.2.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; An\u00e1lise ESTRAT\u00c9GICA. 20<\/a><\/p>\n\n\n\n<p><a href=\"#_Toc44840520\">DIREITO PROCESSUAL PENAL. 21<\/a><\/p>\n\n\n\n<p><a href=\"#_Toc44840521\">11.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Habeas Corpus concomitantemente ao recurso cab\u00edvel 21<\/a><\/p>\n\n\n\n<p><a href=\"#_Toc44840522\">11.1.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Situa\u00e7\u00e3o F\u00c1TICA. 22<\/a><\/p>\n\n\n\n<p><a href=\"#_Toc44840523\">11.2.&nbsp;&nbsp;&nbsp;&nbsp; An\u00e1lise ESTRAT\u00c9GICA. 22<\/a><\/p>\n\n\n\n<p><a href=\"#_Toc44840524\">PARA TESTAR SEU CONHECIMENTO&#8230; 24<\/a><\/p>\n\n\n\n<p><a href=\"#_Toc44840525\">12.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; QUEST\u00d5ES. 24<\/a><\/p>\n\n\n\n<p><a href=\"#_Toc44840526\">12.1.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Quest\u00f5es objetivas: CERTO ou ERRADO. 24<\/a><\/p>\n\n\n\n<p><a href=\"#_Toc44840527\">12.2.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Gabarito. 24<\/a><\/p>\n\n\n\n<h1 class=\"wp-block-heading\"><a>DIREITO CONSTITUCIONAL<\/a><\/h1>\n\n\n\n<h2 class=\"wp-block-heading\"><a>1.&nbsp;&nbsp;&nbsp; Reclama\u00e7\u00e3o para controle de aplica\u00e7\u00e3o de entendimento firmado pelo STJ<\/a><\/h2>\n\n\n\n<p><strong>RECLAMA\u00c7\u00c3O<\/strong><\/p>\n\n\n\n<p>N\u00e3o cabe reclama\u00e7\u00e3o para o controle da aplica\u00e7\u00e3o de entendimento firmado pelo STJ em recurso especial repetitivo.<\/p>\n\n\n\n<p>Rcl 36.476-SP, Rel. Min. Nancy Andrighi, Corte Especial, por maioria, julgado em 05\/02\/2020, DJe 06\/03\/2020<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><a>1.1. Situa\u00e7\u00e3o F\u00c1TICA.<\/a><\/h3>\n\n\n\n<p>Companhia telef\u00f4nica foi condenada em a\u00e7\u00e3o civil p\u00fablica proposta pelo Minist\u00e9rio P\u00fablico do Estado de S\u00e3o Paulo a emitir diferen\u00e7a de a\u00e7\u00f5es, ou a pagar, \u201cna forma mais favor\u00e1vel ao consumidor\u201d, valores em favor dos consumidores que, mediante contrato de participa\u00e7\u00e3o financeira, adquiriram plano de expans\u00e3o de linha telef\u00f4nica.<\/p>\n\n\n\n<p>Posteriormente, os autores da a\u00e7\u00e3o, em cumprimento individual de senten\u00e7a coletiva, buscaram a condena\u00e7\u00e3o da companhia telef\u00f4nica em indenizar pelos preju\u00edzos sofridos, alegando que houvera entrega a menor das a\u00e7\u00f5es cab\u00edveis.<\/p>\n\n\n\n<p>Em embargos de declara\u00e7\u00e3o o TJSP esclareceu que \u201cn\u00e3o sendo poss\u00edvel a entrega das a\u00e7\u00f5es, o valor da indeniza\u00e7\u00e3o deve corresponder ao <em>n\u00famero de a\u00e7\u00f5es a que a parte tinha direito na data da integraliza\u00e7\u00e3o multiplicada pela cota\u00e7\u00e3o na Bolsa de Valores no dia do tr\u00e2nsito em julgado da demanda<\/em>\u201d.<\/p>\n\n\n\n<p>Os autores da a\u00e7\u00e3o entendem que o TJSP errou ao entender pela aplicabilidade da tese firmada no Recurso Especial Repetitivo n. 1.389.989\/RS (e negar processamento do respectivo recurso especial). Para eles, a pretens\u00e3o trazida ao judici\u00e1rio \u00e9 de indeniza\u00e7\u00e3o dos valores das a\u00e7\u00f5es entregues a menor com poss\u00edvel convers\u00e3o em perdas e danos, e N\u00c3O a emiss\u00e3o dessas a\u00e7\u00f5es.<\/p>\n\n\n\n<p>Por isso, em via de RECLAMA\u00c7\u00c3O (prevista no art. 988, IV, do CPC\/2015), pretendem o processamento do Recurso Especial.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><a>1.2. An\u00e1lise ESTRAT\u00c9GICA.<\/a><\/h3>\n\n\n\n<h4 class=\"wp-block-heading\">1.2.1.&nbsp;&nbsp;&nbsp;&nbsp; Cabe RECLAMA\u00c7\u00c3O para aplica\u00e7\u00e3o de entendimento firmado do STJ em Recurso Especial Repetitivo?<\/h4>\n\n\n\n<p>R: <strong>N\u00c3O<\/strong> cabe.<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Em sua reda\u00e7\u00e3o original, o art. 988, IV, do CPC\/2015, previa o cabimento de reclama\u00e7\u00e3o para garantir a observ\u00e2ncia de precedente proferido em julgamento de &#8220;casos repetitivos&#8221;, os quais, conforme o disposto no art. 928 do mesmo C\u00f3digo, abrangem o incidente de resolu\u00e7\u00e3o de demandas repetitivas (IRDR) e os recursos especial e extraordin\u00e1rio repetitivos.<\/p>\n\n\n\n<p>Todavia, <strong>ainda no per\u00edodo de <em>vacatio legis<\/em><\/strong> do CPC\/2015, <strong>o art. 988, IV, foi <\/strong><strong>modificado<\/strong><strong> pela Lei n. 13.256\/2016<\/strong>: <strong>a anterior previs\u00e3o de reclama\u00e7\u00e3o para garantir a observ\u00e2ncia de precedente oriundo de<\/strong> <strong>&#8220;casos repetitivos&#8221; foi EXCLU\u00cdDA<\/strong>, passando a constar, nas hip\u00f3teses de cabimento, apenas o precedente oriundo de IRDR, que \u00e9 esp\u00e9cie daquele.<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Houve, portanto, a SUPRESS\u00c3O do cabimento da reclama\u00e7\u00e3o para a observ\u00e2ncia de ac\u00f3rd\u00e3o proferido em recursos especial e extraordin\u00e1rio repetitivos<strong>,<\/strong> em que pese a mesma Lei n. 13.256\/2016, <em>paradoxalmente<\/em>, tenha acrescentado um pressuposto de admissibilidade, consistente no esgotamento das inst\u00e2ncias ordin\u00e1rias \u00e0 hip\u00f3tese que acabara de excluir.<\/p>\n\n\n\n<p>Sob um aspecto topol\u00f3gico, \u00e0 luz do disposto no art. 11 da LC n. 95\/1998, n\u00e3o h\u00e1 coer\u00eancia e l\u00f3gica em se afirmar que o par\u00e1grafo 5\u00ba, II, do art. 988, do CPC, com a reda\u00e7\u00e3o dada pela Lei n. 13.256\/2016, veicularia uma nova hip\u00f3tese de cabimento da reclama\u00e7\u00e3o. Estas hip\u00f3teses foram elencadas pelos incisos do <em>caput<\/em>, sendo que, por outro lado, o par\u00e1grafo se inicia anunciando que trataria de situa\u00e7\u00f5es de inadmissibilidade da reclama\u00e7\u00e3o.<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; A investiga\u00e7\u00e3o do contexto jur\u00eddico-pol\u00edtico em que foi editada a Lei n. 13.256\/2016 revela que, dentre outras quest\u00f5es, a norma efetivamente visou ao fim da reclama\u00e7\u00e3o dirigida ao STJ e ao STF para o controle da aplica\u00e7\u00e3o dos ac\u00f3rd\u00e3os sobre quest\u00f5es repetitivas, tratando-se de op\u00e7\u00e3o de pol\u00edtica judici\u00e1ria para DESAFOGAR os trabalhos nas Cortes de superposi\u00e7\u00e3o.<\/p>\n\n\n\n<p>Outrossim, a admiss\u00e3o da reclama\u00e7\u00e3o, na hip\u00f3tese em comento, atenta contra a finalidade da institui\u00e7\u00e3o do regime dos recursos especiais repetitivos, que surgiu como mecanismo de RACIONALIZA\u00c7\u00c3O da presta\u00e7\u00e3o jurisdicional do STJ, perante o fen\u00f4meno social da massifica\u00e7\u00e3o dos lit\u00edgios.<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Nesse regime, o STJ se desincumbe de seu m\u00fanus constitucional definindo mediante julgamento por amostragem, a interpreta\u00e7\u00e3o da lei federal que deve ser obrigatoriamente observada pelas inst\u00e2ncias ordin\u00e1rias. Uma vez<strong> uniformizado o direito, \u00e9 dos ju\u00edzes e Tribunais locais a incumb\u00eancia de <u>aplica\u00e7\u00e3o individualizada<\/u> da tese jur\u00eddica em cada caso concreto<\/strong>.<\/p>\n\n\n\n<p>Em tal sistem\u00e1tica, a aplica\u00e7\u00e3o em concreto do precedente N\u00c3O est\u00e1 imune \u00e0 revis\u00e3o, que se d\u00e1 na via recursal ordin\u00e1ria, at\u00e9 eventualmente culminar no julgamento, no \u00e2mbito do Tribunal local, do agravo interno de que trata o art. 1.030, \u00a7 2\u00ba, do CPC\/2015.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">1.2.2.&nbsp; Resultado final.<\/h4>\n\n\n\n<p>Incab\u00edvel a reclama\u00e7\u00e3o constitucional como instrumento de controle da aplica\u00e7\u00e3o dos entendimentos firmados pelo STJ em recursos especiais repetitivos. Tal controle deve ser realizado pela via recursal ordin\u00e1ria e, excepcionalmente, por a\u00e7\u00e3o rescis\u00f3ria, conforme intento do legislador no CPC.<\/p>\n\n\n\n<h1 class=\"wp-block-heading\"><a>DIREITO ADMINISTRATIVO<\/a><\/h1>\n\n\n\n<h2 class=\"wp-block-heading\"><a>2.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Exame de sufici\u00eancia para t\u00e9cnicos em contabilidade formados antes da Lei n. 12.249\/10<\/a><\/h2>\n\n\n\n<p><strong>AGRAVO INTERNO EM RECURSO ESPECIAL<\/strong><\/p>\n\n\n\n<p>\u00c9 dispens\u00e1vel a submiss\u00e3o ao exame de sufici\u00eancia pelos t\u00e9cnicos em contabilidade formados anteriormente \u00e0 promulga\u00e7\u00e3o da Lei n. 12.249\/2010 ou dentro do prazo por ela previsto.<\/p>\n\n\n\n<p>AgInt no REsp 1.830.687-RS, Rel. Min. S\u00e9rgio Kukina, Primeira Turma, por unanimidade, julgado em 30\/03\/2020, D. Je 02\/04\/2020<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><a>2.1.&nbsp; Situa\u00e7\u00e3o F\u00c1TICA.<\/a><\/h3>\n\n\n\n<p>Creosvaldo concluiu o curso de t\u00e9cnico em contabilidade no ano de 1999. S\u00f3 que ele \u00e9 meio dorminhoco (se \u00e9 que me entende&#8230;). O tempo passou e ele foi \u201cempurrando com a barriga\u201d a solicita\u00e7\u00e3o do registro no \u00f3rg\u00e3o de classe, o que acabou fazendo apenas a lei n. 12.249\/2010 ter entrado em vig\u00eancia.<\/p>\n\n\n\n<p>Pois qual foi a surpresa de Creosvaldo ao ter seu pedido administrativo de registro negado. A justificativa? A nova lei exige a aprova\u00e7\u00e3o em exame de sufici\u00eancia.<\/p>\n\n\n\n<p>E agora Jos\u00e9? Digo, Creosvaldo?<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><a>2.2. An\u00e1lise ESTRAT\u00c9GICA.<\/a><\/h3>\n\n\n\n<h4 class=\"wp-block-heading\">2.2.1.&nbsp;&nbsp;&nbsp;&nbsp; O exame de sufici\u00eancia \u00e9 obrigat\u00f3rio para t\u00e9cnicos em contabilidade formados antes da lei 12.249\/2010?<\/h4>\n\n\n\n<p><strong><em><u>R:<\/u><\/em><\/strong> <strong>N\u00c3O.<\/strong><\/p>\n\n\n\n<p>A <strong>implementa\u00e7\u00e3o dos requisitos<\/strong> para a inscri\u00e7\u00e3o no conselho profissional surge no momento da CONCLUS\u00c3O do curso. Assim, \u00e9 dispens\u00e1vel <strong><u>a submiss\u00e3o ao exame de sufici\u00eancia pelos t\u00e9cnicos em contabilidade formados anteriormente <\/u><\/strong>\u00e0 promulga\u00e7\u00e3o da Lei n. 12.249\/2010 ou dentro do prazo por ela previsto.<\/p>\n\n\n\n<p>Desse modo, nos casos de conclus\u00e3o do curso de t\u00e9cnico em contabilidade em data anterior \u00e0 vig\u00eancia da Lei n. 12.249\/2010, <strong>h\u00e1 que se reconhecer a exist\u00eancia de <\/strong><strong>direito adquirido<\/strong><strong> \u00e0 inscri\u00e7\u00e3o perante o respectivo conselho de classe<\/strong>, ainda que o pedido de registro junto ao \u00f3rg\u00e3o tenha ocorrido posteriormente \u00e0 data prevista na lei supracitada.<\/p>\n\n\n\n<p><em>Para fins de requisitos para a inscri\u00e7\u00e3o em conselho profissional, o que vale \u00e9 a CONCLUS\u00c3O do respectivo curso, e n\u00e3o o PEDIDO administrativo de registro.<\/em><\/p>\n\n\n\n<h4 class=\"wp-block-heading\">2.2.2.&nbsp; Resultado final.<\/h4>\n\n\n\n<p>\u00c9 dispens\u00e1vel a submiss\u00e3o ao exame de sufici\u00eancia pelos t\u00e9cnicos em contabilidade formados anteriormente \u00e0 promulga\u00e7\u00e3o da Lei n. 12.249\/2010 ou dentro do prazo por ela previsto, por se verificar a exist\u00eancia de direito adquirido no momento da conclus\u00e3o do curso.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><a>3.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Fixa\u00e7\u00e3o de cau\u00e7\u00e3o em valor diverso do previsto na lei de licita\u00e7\u00f5es<\/a><\/h2>\n\n\n\n<p><strong>RECURSO ESPECIAL<\/strong><\/p>\n\n\n\n<p>Na concorr\u00eancia para a venda de bens im\u00f3veis, \u00e9 vedada, \u00e0 Administra\u00e7\u00e3o P\u00fablica, a fixa\u00e7\u00e3o de cau\u00e7\u00e3o em valor diverso do estabelecido no art. 18 da Lei n. 8.666\/1993.<\/p>\n\n\n\n<p>REsp 1.617.745-DF, Rel. Min. Og Fernandes, Rel. Acd. Min. Assusete Magalh\u00e3es, Segunda Turma, por maioria, julgado em 22\/10\/2019, DJe 16\/04\/2020<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><a>3.1. Situa\u00e7\u00e3o F\u00c1TICA.<\/a><\/h3>\n\n\n\n<p>Em edital de licita\u00e7\u00e3o na modalidade concorr\u00eancia (para a venda de bens im\u00f3veis) constou a possibilidade de cau\u00e7\u00e3o no valor de 1% da avalia\u00e7\u00e3o do im\u00f3vel. Licitantes menores ficaram mais do que felizes e inundaram o certamente.<\/p>\n\n\n\n<p>S\u00f3 que os participantes maiores n\u00e3o gostaram nada nada da inova\u00e7\u00e3o e buscaram a anula\u00e7\u00e3o do ato administrativo de homologa\u00e7\u00e3o do processo, alegando viola\u00e7\u00e3o do disposto no art. 18 da lei de licita\u00e7\u00f5es \u2014 que prev\u00ea o percentual de 5% para a cau\u00e7\u00e3o.<\/p>\n\n\n\n<p>No ju\u00edzo de segundo grau, foi proferida decis\u00e3o no sentido de que a previs\u00e3o na lei 8.666\/1993 estabelece o limite da cau\u00e7\u00e3o e <em>n\u00e3o seu valor exato<\/em>, podendo a Administra\u00e7\u00e3o P\u00fablica fixar cau\u00e7\u00e3o em valor inferior a 5% da avalia\u00e7\u00e3o do im\u00f3vel, se entender pertinente (discricionariedade regrada).<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><a>3.2. An\u00e1lise ESTRAT\u00c9GICA.<\/a><\/h3>\n\n\n\n<h4 class=\"wp-block-heading\">3.2.1.&nbsp;&nbsp;&nbsp;&nbsp; Quest\u00e3o JUR\u00cdDICA<\/h4>\n\n\n\n<p>Lei n. 8.666\/1993, art. 18: &#8220;Na concorr\u00eancia para a venda de bens im\u00f3veis, a fase de habilita\u00e7\u00e3o limitar-se-\u00e1 \u00e0 comprova\u00e7\u00e3o do recolhimento de quantia correspondente a 5% (cinco por cento) da avalia\u00e7\u00e3o\u201d.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">3.2.2.&nbsp;&nbsp;&nbsp;&nbsp; Pode a Administra\u00e7\u00e3o P\u00fablica estipular valor de cau\u00e7\u00e3o distinto do previsto na lei de licita\u00e7\u00f5es para a venda de bens im\u00f3veis?<\/h4>\n\n\n\n<p><strong><em><u>R:<\/u><\/em><\/strong> <strong>N\u00c3O.<\/strong><\/p>\n\n\n\n<p>Da interpreta\u00e7\u00e3o TELEOL\u00d3GICA do artigo 18 da Lei de Licita\u00e7\u00f5es, depreende-se que o legislador estabeleceu o valor da cau\u00e7\u00e3o com intuito de <strong>aferir a capacidade econ\u00f4mica da licitante<\/strong>, exigindo-se o dep\u00f3sito da garantia, de forma a demonstrar a sua APTID\u00c3O FINANCEIRA para garantir a execu\u00e7\u00e3o do contrato.<\/p>\n\n\n\n<p><em>A Administra\u00e7\u00e3o est\u00e1 vinculada aos ditames legais, subordinando-se o administrador ao princ\u00edpio da legalidade inserido no art. 37 da CF\/88.<\/em><\/p>\n\n\n\n<p>Nesse contexto, verifica-se queo valor da cau\u00e7\u00e3o visa precipuamente \u00e0 <strong><u>garantia da execu\u00e7\u00e3o do contrato<\/u><\/strong>, sendovedado<strong>, <\/strong>\u00e0 Administra\u00e7\u00e3o P\u00fablica, afixa\u00e7\u00e3o de cau\u00e7\u00e3o em valor diverso do estabelecido em lei.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">3.2.3.&nbsp; Resultado final.<\/h4>\n\n\n\n<p>Na concorr\u00eancia para a venda de bens im\u00f3veis, \u00e9 vedada, \u00e0 Administra\u00e7\u00e3o P\u00fablica, a fixa\u00e7\u00e3o de cau\u00e7\u00e3o em valor diverso do estabelecido no art. 18 da Lei n. 8.666\/1993 e obedi\u00eancia ao princ\u00edpio constitucional da legalidade.<\/p>\n\n\n\n<h1 class=\"wp-block-heading\"><a>DIREITO CIVIL<\/a><\/h1>\n\n\n\n<h2 class=\"wp-block-heading\"><a>4.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Legalidade da imputa\u00e7\u00e3o ao pagamento primeiramente nos juros<\/a><\/h2>\n\n\n\n<p><strong>AGRAVO INTERNO NO RECURSO ESPECIAL<\/strong><\/p>\n\n\n\n<p>No pagamento diferido em parcelas, n\u00e3o havendo disposi\u00e7\u00e3o contratual em contr\u00e1rio, \u00e9 legal a imputa\u00e7\u00e3o do pagamento primeiramente nos juros.<\/p>\n\n\n\n<p>AgInt no REsp 1.843.073-SP, Rel. Min. Marco Aur\u00e9lio Bellizze, Terceira Turma, por unanimidade, julgado em 30\/03\/2020, DJe 06\/04\/2020<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><a>4.1. Situa\u00e7\u00e3o F\u00c1TICA.<\/a><\/h3>\n\n\n\n<p>Josefina abriu uma conta corrente com cheque especial e adorou esse neg\u00f3cio de assinar peda\u00e7os de papel com os quais podia adquirir mercadorias (saciar seus desejos). S\u00f3 que, como acontece com muitos brasileiros, deixou a coisas degringolar (as contas n\u00e3o cabiam no or\u00e7amento). Passou a usar o famoso \u201climite\u201d e a pagar juros sobre o capital.<\/p>\n\n\n\n<p>Ela depositava algum valor na conta todos os meses (n\u00e3o o suficiente para quitar a d\u00edvida, mas apenas para abat\u00ea-la), mas o montante devido continuava aumentando exponencialmente (bola de neve). Ela ent\u00e3o ajuizou a\u00e7\u00e3o revisional e de repeti\u00e7\u00e3o de ind\u00e9bito sob o argumento de h\u00e1 capitaliza\u00e7\u00e3o indevida (juros sobre juros), e que n\u00e3o consta previs\u00e3o espec\u00edfica no contrato a imputar o pagamento no principal e n\u00e3o nos juros.<\/p>\n\n\n\n<p>Em sede de recurso, o Tribunal competente n\u00e3o deu bola para as teses de Josefina: entendeu vi\u00e1vel a capitaliza\u00e7\u00e3o mensal dos juros e a preval\u00eancia das condi\u00e7\u00f5es pactuadas no contrato.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><a>4.2. An\u00e1lise ESTRAT\u00c9GICA.<\/a><\/h3>\n\n\n\n<h4 class=\"wp-block-heading\">4.2.1.&nbsp;&nbsp;&nbsp;&nbsp; Quest\u00e3o JUR\u00cdDICA<\/h4>\n\n\n\n<p>CC, Art. 354. Havendo capital e juros, o pagamento imputar-se-\u00e1 primeiro nos juros vencidos, e depois no capital, salvo estipula\u00e7\u00e3o em contr\u00e1rio, ou se o credor passar a quita\u00e7\u00e3o por conta do capital.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">4.2.2.&nbsp;&nbsp;&nbsp;&nbsp; Em contrato sem previs\u00e3o no sentido contr\u00e1rio, \u00e9 legal a imputa\u00e7\u00e3o do pagamento primeiramente nos juros?<\/h4>\n\n\n\n<p><strong><em><u>R:<\/u><\/em><\/strong> <strong>SIM.<\/strong><\/p>\n\n\n\n<p>A imputa\u00e7\u00e3o dos pagamentos primeiramente nos juros \u00e9 instituto que, via de regra, <strong>alcan\u00e7a TODOS os contratos em que o pagamento \u00e9 diferido em parcelas<\/strong>, porquanto tem por objetivo diminuir a onera\u00e7\u00e3o do devedor, <em>evitando-se que os juros sejam integrados ao capital para somente depois abater o valor das presta\u00e7\u00f5es<\/em>, de modo a evitar que sobre eles incida novo c\u00f4mputo de juros (juros sobre juros, efeito cascata e bola de neve).<\/p>\n\n\n\n<p>Nessa linha \u00e9 a jurisprud\u00eancia do Superior Tribunal de Justi\u00e7a, admitindo a utiliza\u00e7\u00e3o do instituto quando o contrato n\u00e3o disponha expressamente em contr\u00e1rio.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">4.2.3.&nbsp; Resultado final.<\/h4>\n\n\n\n<p>No pagamento diferido em parcelas, n\u00e3o havendo disposi\u00e7\u00e3o contratual em contr\u00e1rio, \u00e9 legal a imputa\u00e7\u00e3o do pagamento primeiramente nos juros.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><a>5.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Circunst\u00e2ncias permissivas para a desonera\u00e7\u00e3o de alimentos fixados entre ex-c\u00f4njuges<\/a><\/h2>\n\n\n\n<p><strong>RECURSO ESPECIAL<\/strong><\/p>\n\n\n\n<p>A desonera\u00e7\u00e3o dos alimentos fixados entre ex-c\u00f4njuges deve considerar outras circunst\u00e2ncias, al\u00e9m do bin\u00f4mio necessidade-possibilidade, tais como a capacidade potencial para o trabalho e o tempo de pensionamento.<\/p>\n\n\n\n<p>REsp 1.829.295-SC, Rel. Min. Paulo de Tarso Sanseverino, Terceira Turma, por unanimidade, julgado em 10\/03\/2020, DJe 13\/03\/2020<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><a>5.1. Situa\u00e7\u00e3o F\u00c1TICA.<\/a><\/h3>\n\n\n\n<p>Pedro Pedregulho ajuizou a\u00e7\u00e3o pretendendo se desonerar da obriga\u00e7\u00e3o de alimentos fixada em div\u00f3rcio ocorrido no ano de 2008. Sustentou que, al\u00e9m do grande lapso de tempo cumprindo a obriga\u00e7\u00e3o, Manuela (a alimentanda) \u00e9 graduada em diferentes \u00e1reas e por esta raz\u00e3o poderia arcar com o pr\u00f3prio sustento.<\/p>\n\n\n\n<p>Em primeira inst\u00e2ncia o ju\u00edzo acolheu o pedido do autor em julgamento antecipado da lide. A senten\u00e7a foi reformada sob a fundamenta\u00e7\u00e3o de que n\u00e3o restou comprovada a ociosidade ou a des\u00eddia de Manuela com os recursos provenientes da pens\u00e3o.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><a>5.2. An\u00e1lise ESTRAT\u00c9GICA.<\/a><\/h3>\n\n\n\n<h4 class=\"wp-block-heading\">5.2.1.&nbsp;&nbsp;&nbsp;&nbsp; \u00c9 v\u00e1lida a desonera\u00e7\u00e3o de alimentos decidida com base em circunst\u00e2ncias al\u00e9m do bin\u00f4mio necessidade\/possibilidade?<\/h4>\n\n\n\n<p><strong><em><u>R:<\/u><\/em><\/strong> <strong>SIM.<\/strong><\/p>\n\n\n\n<p>\u00c9 cada vez mais firme o entendimento de que os alimentos devidos entre ex-c\u00f4njuges t\u00eam car\u00e1ter EXCEPCIONAL e TRANSIT\u00d3RIO, <strong>salvo quando presentes particularidades que justifiquem a prorroga\u00e7\u00e3o da obriga\u00e7\u00e3o<\/strong>, tais como a incapacidade laborativa, a impossibilidade de (re)inser\u00e7\u00e3o no mercado de trabalho ou de adquirir autonomia financeira.<\/p>\n\n\n\n<p>H\u00e1 algum tempo, a Terceira Turma do STJ vem reafirmando que &#8220;os alimentos devidos entre ex-c\u00f4njuges ser\u00e3o fixados com TERMO CERTO, a depender das circunst\u00e2ncias f\u00e1ticas pr\u00f3prias da hip\u00f3tese sob discuss\u00e3o, assegurando-se, ao alimentado, tempo h\u00e1bil para sua inser\u00e7\u00e3o, recoloca\u00e7\u00e3o ou progress\u00e3o no mercado de trabalho, que lhe possibilite manter pelas pr\u00f3prias for\u00e7as, status social similar ao per\u00edodo do relacionamento&#8221;.<\/p>\n\n\n\n<p>Al\u00e9m disso, tem-se afirmado que, &#8220;se os alimentos devidos a ex-c\u00f4njuge n\u00e3o forem fixados por termo certo, o pedido de desonera\u00e7\u00e3o total, ou parcial, <strong>poder\u00e1 <\/strong>dispensar<strong> a exist\u00eancia de VARIA\u00c7\u00c3O no <\/strong>bin\u00f4mio necessidade\/possibilidade, quando demonstrado o pagamento de pens\u00e3o por lapso temporal suficiente para que o alimentado revertesse a condi\u00e7\u00e3o desfavor\u00e1vel que detinha, no momento da fixa\u00e7\u00e3o desses alimentos&#8221; (REsp 1.205.408\/RJ, Rel. Ministra NANCY ANDRIGHI, TERCEIRA TURMA, julgado em 21\/06\/2011, DJe 29\/06\/2011).<\/p>\n\n\n\n<p>Assim, outras circunst\u00e2ncias devem ser examinadas no julgamento de demandas desse jaez, tais como a capacidade potencial para o trabalho do alimentando, bem assim o<strong> tempo decorrido entre o seu in\u00edcio e a data do pedido de desonera\u00e7\u00e3o.<\/strong><\/p>\n\n\n\n<h4 class=\"wp-block-heading\">5.2.2.&nbsp; Resultado final.<\/h4>\n\n\n\n<p>A desonera\u00e7\u00e3o dos alimentos fixados entre ex-c\u00f4njuges deve considerar outras circunst\u00e2ncias, al\u00e9m do bin\u00f4mio necessidade-possibilidade, tais como a capacidade potencial para o trabalho e o tempo de pensionamento.<\/p>\n\n\n\n<h1 class=\"wp-block-heading\"><a>DIREITO PROCESSUAL CIVIL<\/a><\/h1>\n\n\n\n<h2 class=\"wp-block-heading\"><a>6.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Ponto facultativo baseado em ato do Executivo estadual e tempestividade recursal<\/a><\/h2>\n\n\n\n<p><strong>EMBARGOS DE DECLARA\u00c7\u00c3O EM AGRAVO INTERNO<\/strong><\/p>\n\n\n\n<p>A alega\u00e7\u00e3o da ocorr\u00eancia de ponto facultativo embasada em ato do Poder Executivo Estadual n\u00e3o \u00e9 capaz, por si s\u00f3, de comprovar a inexist\u00eancia de expediente forense para aferi\u00e7\u00e3o da tempestividade recursal.<\/p>\n\n\n\n<p>EDcl no AgInt no AREsp 1.510.568-RJ, Rel. Min. Marco Aur\u00e9lio Bellizze, Terceira Turma, por unanimidade, julgado em 23\/03\/2020, DJe 30\/03\/2020<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><a>6.1. Situa\u00e7\u00e3o F\u00c1TICA.<\/a><\/h3>\n\n\n\n<p>Os caus\u00eddicos que defendem os interesses de Crementina foram intimados do ac\u00f3rd\u00e3o proferido na a\u00e7\u00e3o em 20\/04\/2018. &nbsp;Eles interpuseram o recurso especial em 16\/05\/2018, o qual foi declarado intempestivo. Crementina pirou, mas eles disseram: <em>\u201cDeixa com noix!!! Tinha feriado no meio desse bolo!\u201d<\/em><\/p>\n\n\n\n<p>Os advogados ent\u00e3o sustentaram que em raz\u00e3o do feriado estadual carioca de 23\/04\/2018 (dia de S\u00e3o Jorge), houve suspens\u00e3o dos prazos no TJRJ de 25\/04\/2018 a 27\/04\/2018, bem como ponto facultativo em 30\/04\/2018. Assim sendo, o prazo para o recurso somente teria iniciado em 24\/04\/2018 e, portanto, o recurso teria sido protocolado dentro do lapso legal.<\/p>\n\n\n\n<p>Para comprovar essa tese, a banca juntou aos autos documentos extra\u00eddos da internet (calend\u00e1rio de expedientes e feriados do TJRJ), de modo a comprovar a falta de expediente nos dias citados.&nbsp;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><a>6.2. An\u00e1lise ESTRAT\u00c9GICA.<\/a><\/h3>\n\n\n\n<h4 class=\"wp-block-heading\">6.2.1.&nbsp;&nbsp;&nbsp;&nbsp; Ponto facultativo previsto em ato emanado pelo Poder Executivo Estadual, por si s\u00f3, pode comprovar a aus\u00eancia de expediente forense?<\/h4>\n\n\n\n<p><strong><em><u>R:<\/u><\/em><\/strong> . <strong>N\u00c3O<\/strong><\/p>\n\n\n\n<p>A jurisprud\u00eancia do STJ entende que a exist\u00eancia de feriado, de recesso forense ou ponto facultativo local que ocasione a suspens\u00e3o do prazo processual necessita de COMPROVA\u00c7\u00c3O por <strong>documento id\u00f4neo<\/strong>.<\/p>\n\n\n\n<p>Por documento id\u00f4neo entenda-se:<strong> <\/strong>c\u00f3pia da lei, ato normativo ou certid\u00e3o exarada por servidor habilitado.<\/p>\n\n\n\n<p>Logo, a simples juntada de ato emanado pelo Poder Executivo Estadual, lei e decreto estaduais, determinando ponto facultativo nas reparti\u00e7\u00f5es p\u00fablicas estaduais, por si s\u00f3, N\u00c3O comprova a inexist\u00eancia de expediente forense para aferi\u00e7\u00e3o da tempestividade do recurso, em raz\u00e3o da desvincula\u00e7\u00e3o administrativa e da separa\u00e7\u00e3o entre os Poderes.<\/p>\n\n\n\n<p>Da mesma forma, a juntada de calend\u00e1rio extra\u00eddo de p\u00e1ginas da internet (mesmo o de expedientes e feriados do Tribunal???) N\u00c3O \u00e9 meio id\u00f4neo para comprova\u00e7\u00e3o da tempestividade recursal.<\/p>\n\n\n\n<p><strong>Caberia \u00e0 recorrente, no momento da interposi\u00e7\u00e3o recursal, fazer a juntada de documento id\u00f4neo<\/strong>, o qual, no caso, consistianoINTEIRO TEOR do Aviso do tribunal estadual, a fim de vincular a decreta\u00e7\u00e3o do feriado nas reparti\u00e7\u00f5es p\u00fablicas estaduais com a suspens\u00e3o dos prazos pela Corte de Justi\u00e7a.<\/p>\n\n\n\n<p><strong>JURISPRUD\u00caNCIA DEFENSIVA<\/strong>: supervaloriza\u00e7\u00e3o de requisitos formais para inviabilizar a aprecia\u00e7\u00e3o do m\u00e9rito recursal. Trata-se da cria\u00e7\u00e3o de \u201cfiltros\u201d (obst\u00e1culos) para \u201cgerenciar\u201d o volume de recursos e a carga de trabalho. S\u00e3o verdadeiras &#8220;granadas hermen\u00eauticas&#8221; que servem para mutilar as expectativas dos jurisdicionados de justi\u00e7a e s\u00e3o utilizadas pelos tribunais para fulminar recursos (Marcelo Mazzola).<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">6.2.2.&nbsp; Resultado final.<\/h4>\n\n\n\n<p>A alega\u00e7\u00e3o da ocorr\u00eancia de ponto facultativo embasada em ato do Poder Executivo Estadual n\u00e3o \u00e9 capaz, por si s\u00f3, de comprovar a inexist\u00eancia de expediente forense para aferi\u00e7\u00e3o da tempestividade recursal. Para tanto \u00e9 indispens\u00e1vel a juntada de documento id\u00f4neo que comprove a falta de expediente forense na data questionada.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><a>7.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Acolhimento de impugna\u00e7\u00e3o ao valor da causa em momento posterior \u00e0 an\u00e1lise m\u00e9rito<\/a><\/h2>\n\n\n\n<p><strong>AGRAVO INTERNO EM RECURSO ESPECIAL<\/strong><\/p>\n\n\n\n<p>O acolhimento da impugna\u00e7\u00e3o do valor da causa em momento posterior \u00e0 decis\u00e3o que julgou o m\u00e9rito da causa principal n\u00e3o gera nulidade do processo.<\/p>\n\n\n\n<p>AgInt no REsp 1.667.308-SP, Rel. Min. Paulo de Tarso Sanseverino, Terceira Turma, por unanimidade, julgado em 30\/03\/2020, DJe 01\/04\/2020<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><a>7.1. Situa\u00e7\u00e3o F\u00c1TICA.<\/a><\/h3>\n\n\n\n<p>Josefina deixou de pagar umas contas e teve um im\u00f3vel penhorado na respectiva a\u00e7\u00e3o de execu\u00e7\u00e3o. O im\u00f3vel foi avaliado em R$ 24.500,00 no ano de 2008 e arrematado por 50% do valor da avalia\u00e7\u00e3o em 2011.<\/p>\n\n\n\n<p>S\u00f3 que em uma reviravolta, em complementa\u00e7\u00e3o de senten\u00e7a, o juiz\u00e3o acolheu a impugna\u00e7\u00e3o ao valor da causa (o exequente teria dado valor muito baixo \u00e0 execu\u00e7\u00e3o, normalmente para recolher menos custas) e, em momento <strong>posterior ao m\u00e9rito,<\/strong> determinou nova avalia\u00e7\u00e3o do bem (de of\u00edcio).<\/p>\n\n\n\n<p>O exequente foi \u00e0 loucura com o procedimento adotado pelo juiz. Impugnou a decis\u00e3o sob o argumento de que haveria nulidade na decis\u00e3o que acolhe a impugna\u00e7\u00e3o ao valor da causa depois da an\u00e1lise do m\u00e9rito.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><a>7.2.&nbsp; An\u00e1lise ESTRAT\u00c9GICA.<\/a><\/h3>\n\n\n\n<h4 class=\"wp-block-heading\">7.2.1.&nbsp;&nbsp;&nbsp;&nbsp; &nbsp;H\u00e1 nulidade na decis\u00e3o que acolhe a impugna\u00e7\u00e3o ao valor da causa em momento posterior ao m\u00e9rito?<\/h4>\n\n\n\n<p><strong><em><u>R:<\/u><\/em><\/strong> <strong>Negativo<\/strong>.<\/p>\n\n\n\n<p>Primeiramente, a prola\u00e7\u00e3o da decis\u00e3o de acolhimento da impugna\u00e7\u00e3o do valor da causa em momento posterior \u00e0 decis\u00e3o que julga o m\u00e9rito da causa principal constitui mera irregularidade, <strong>n\u00e3o gerando preju\u00edzo suficiente para decreta\u00e7\u00e3o da nulidade do processo<\/strong>.<\/p>\n\n\n\n<p>Ademais, ante o princ\u00edpio da INSTRUMENTALIDADE, atinge seu fim o recolhimento posterior das custas, sem que para tanto seja necess\u00e1ria a decreta\u00e7\u00e3o da nulidade do ato.<\/p>\n\n\n\n<p><em>O princ\u00edpio da instrumentalidade das formas anda sempre de m\u00e3os dadas com o princ\u00edpio da primazia da resolu\u00e7\u00e3o de m\u00e9rito.<\/em><\/p>\n\n\n\n<p>Por fim, no caso o STJ <strong>N\u00c3O<\/strong> vislumbrou preju\u00edzo suficiente para a parte atingida pela irregularidade, pois o recolhimento das custas pode se dar de forma <strong>posterior<\/strong>.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><a>7.2.2.&nbsp;&nbsp;&nbsp;&nbsp; Resultado<\/a> final.<\/h4>\n\n\n\n<p>O acolhimento da impugna\u00e7\u00e3o do valor da causa em momento posterior \u00e0 decis\u00e3o que julgou o m\u00e9rito da causa principal n\u00e3o gera, por si s\u00f3, a nulidade do processo. Trata-se de mera irregularidade que n\u00e3o resulta em preju\u00edzo suficiente a justificar nulidade autom\u00e1tica.<\/p>\n\n\n\n<h1 class=\"wp-block-heading\"><a>DIREITO EMPRESARIAL<\/a><\/h1>\n\n\n\n<h2 class=\"wp-block-heading\"><a>8.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Sujei\u00e7\u00e3o dos honor\u00e1rios sucumbenciais ao ju\u00edzo recuperacional<\/a><\/h2>\n\n\n\n<p><strong>RECURSO ESPECIAL<\/strong><\/p>\n\n\n\n<p>O cr\u00e9dito de honor\u00e1rios advocat\u00edcios sucumbenciais constitu\u00eddo ap\u00f3s o pedido de recupera\u00e7\u00e3o judicial n\u00e3o est\u00e1 submetido ao ju\u00edzo recuperacional, ressalvando-se o controle dos atos expropriat\u00f3rios pelo ju\u00edzo universal.<\/p>\n\n\n\n<p>REsp 1.841.960-SP, Rel. Min. Nancy Andrighi, Rel. Acd. Min. Luis Felipe Salom\u00e3o, Segunda Se\u00e7\u00e3o, por maioria, julgado em 12\/02\/2020, DJe 13\/04\/2020<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><a>8.1. Situa\u00e7\u00e3o F\u00c1TICA.<\/a><\/h3>\n\n\n\n<p>A empresa Cobrotudo S\/A promoveu a\u00e7\u00e3o de execu\u00e7\u00e3o de t\u00edtulo extrajudicial em desfavor de Naufragrandus Ltda. A Naufragandus op\u00f4s embargos \u00e0 execu\u00e7\u00e3o.<\/p>\n\n\n\n<p>S\u00f3 que ent\u00e3o a Naufragrandus requereu recupera\u00e7\u00e3o judicial. Em raz\u00e3o do superveniente deferimento desse pedido, houve suspens\u00e3o do processo executivo. Os embargos \u00e0 execu\u00e7\u00e3o promovidos pela Naufragrandus, de todo modo, foram julgados improcedentes e ela foi condenada ao pagamento de honor\u00e1rios advocat\u00edcios sucumbenciais.<\/p>\n\n\n\n<p>Acontece que o tribunal competente proferiu decis\u00e3o no sentido de determinar o levantamento da penhora e a restitui\u00e7\u00e3o do valor penhorado pela credora (Cobrotudo) em favor do ju\u00edzo da recupera\u00e7\u00e3o, sendo que seria na recupera\u00e7\u00e3o que a credora deveria cobrar a verba honor\u00e1rios rec\u00e9m-adquirida.<\/p>\n\n\n\n<p>Sustenta a Cobrotudo que os honor\u00e1rios advocat\u00edcios decorrentes de decis\u00e3o judicial transitada em julgado ap\u00f3s o pedido da recupera\u00e7\u00e3o judicial devem ser exclu\u00eddos dos seus efeitos, pois segundo a lei s\u00f3 ingressam na recupera\u00e7\u00e3o os cr\u00e9ditos existentes ao tempo do pedido de recupera\u00e7\u00e3o.<\/p>\n\n\n\n<p>A controv\u00e9rsia, portanto, consiste em definir se os cr\u00e9ditos decorrentes de honor\u00e1rios sucumbenciais, oriundos da improced\u00eancia de embargos \u00e0 execu\u00e7\u00e3o opostos anteriormente ao pedido de recupera\u00e7\u00e3o judicial, mas cuja condena\u00e7\u00e3o e tr\u00e2nsito em julgado da senten\u00e7a se deram ap\u00f3s o pleito recuperacional, devem se submeter, ou n\u00e3o, ao plano de soerguimento.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><a>8.2. An\u00e1lise ESTRAT\u00c9GICA.<\/a><\/h3>\n\n\n\n<h4 class=\"wp-block-heading\">8.2.1.&nbsp;&nbsp;&nbsp;&nbsp; Quest\u00e3o JUR\u00cdDICA<\/h4>\n\n\n\n<p>Lei 11.101\/05, Art. 49. Est\u00e3o sujeitos \u00e0 recupera\u00e7\u00e3o judicial todos os cr\u00e9ditos <strong>existentes<\/strong> na data do pedido, ainda que n\u00e3o vencidos.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">8.2.2.&nbsp;&nbsp;&nbsp;&nbsp; Os honor\u00e1rios sucumbenciais provenientes de senten\u00e7a posterior ao pedido de recupera\u00e7\u00e3o judicial s\u00e3o submetidos ao ju\u00edzo recuperacional?<\/h4>\n\n\n\n<p><strong>R: N\u00c3O.<\/strong><strong><\/strong><\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; O STJ possui entendimento vacilante sobre o tema (reconhe\u00e7a-se).<\/p>\n\n\n\n<p>A Terceira Turma inicialmente equiparou os honor\u00e1rios sucumbenciais surgidos posteriormente \u00e0 senten\u00e7a, em desfavor da empresa recuperanda, a cr\u00e9ditos trabalhistas. Assim, submeteu-os aos efeitos da recupera\u00e7\u00e3o judicial.<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; De outra parte, a Quarta Turma e a Segunda Se\u00e7\u00e3o possuem entendimento predominante no sentido de reconhecer que os honor\u00e1rios sucumbenciais surgidos posteriormente ao pleito de recupera\u00e7\u00e3o judicial N\u00c3O se sujeitam aos efeitos do processo de soerguimento (s\u00e3o cr\u00e9ditos extraconcursais), incumbindo ao ju\u00edzo da recupera\u00e7\u00e3o exercer o controle dos atos expropriat\u00f3rios na execu\u00e7\u00e3o particular.<\/p>\n\n\n\n<p>Surpreendentemente, este foi adotado pela Terceira Turma em seu julgamento mais recente sobre a quest\u00e3o (vide: Aglnt nos EDcl no REsp 1.649.186\/RS, DJe 30\/8\/2019).<\/p>\n\n\n\n<p>\u00c9 preciso resolver essa parada!<\/p>\n\n\n\n<p>A <strong>Corte Especial<\/strong> do STJ, no julgamento do EAREsp 1.255.986\/PR, em decis\u00e3o un\u00e2nime, concluiu que <strong>a senten\u00e7a <\/strong>(ou o ato jurisdicional equivalente, na compet\u00eancia origin\u00e1ria dos tribunais)<strong> <u>\u00e9 o ato processual que qualifica o nascedouro do direito \u00e0 percep\u00e7\u00e3o dos honor\u00e1rios<\/u> <\/strong>advocat\u00edcios sucumbenciais.<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Dessarte, em exegese l\u00f3gica e sistem\u00e1tica, se a senten\u00e7a que arbitrou os honor\u00e1rios sucumbenciais se deu posteriormente ao pedido de recupera\u00e7\u00e3o judicial, <strong>o cr\u00e9dito que dali emana, necessariamente, nascer\u00e1 com <\/strong>natureza extraconcursal, j\u00e1 que, nos termos do art. 49, <em>caput<\/em>, da Lei n. 11.101\/2005, sujeitam-se ao plano de soerguimento os cr\u00e9ditos existentes na data do pedido de recupera\u00e7\u00e3o judicial, ainda que n\u00e3o vencidos, e n\u00e3o os posteriores.<\/p>\n\n\n\n<p>Por outro lado, se a senten\u00e7a que arbitrou os honor\u00e1rios advocat\u00edcios for anterior ao pedido recuperacional, o cr\u00e9dito dali decorrente dever\u00e1 ser tido como concursal, devendo ser <strong>habilitado e pago nos termos do plano de recupera\u00e7\u00e3o judicial<\/strong>.<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Ocr\u00e9dito de honor\u00e1rios advocat\u00edcios sucumbenciais constitu\u00eddo AP\u00d3S o pedido recuperacionalN\u00c3O se sujeita<strong> ao plano de soerguimento <\/strong>e as execu\u00e7\u00f5es prosseguem, mas o ju\u00edzo universal deve exercer o controle sobre atos constritivos de patrim\u00f4nio, aquilatando a essencialidade do bem \u00e0 atividade empresarial.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">8.2.3.&nbsp; Resultado final.<\/h4>\n\n\n\n<p>O cr\u00e9dito de honor\u00e1rios advocat\u00edcios sucumbenciais constitu\u00eddo ap\u00f3s o pedido de recupera\u00e7\u00e3o judicial n\u00e3o est\u00e1 submetido ao ju\u00edzo recuperacional, ressalvando-se o controle dos atos expropriat\u00f3rios pelo ju\u00edzo universal.<\/p>\n\n\n\n<h1 class=\"wp-block-heading\"><a>DIREITO TRIBUT\u00c1RIO<\/a><\/h1>\n\n\n\n<h2 class=\"wp-block-heading\"><a>9.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Cr\u00e9dito presumido PIS\/PASEP e Cofins para cerealistas<\/a><\/h2>\n\n\n\n<p><strong>RECURSO ESPECIAL<\/strong><\/p>\n\n\n\n<p>T\u00eam direito ao cr\u00e9dito presumido de PIS\/PASEP e Cofins as pessoas jur\u00eddicas, inclusive cooperativas, que produzam mercadorias por meio de processo de industrializa\u00e7\u00e3o de gr\u00e3os de soja, milho e trigo adquiridos de pessoa f\u00edsica, cerealista ou cooperado pessoa f\u00edsica, enquanto os meros cerealistas n\u00e3o t\u00eam direito ao cr\u00e9dito presumido.<\/p>\n\n\n\n<p>REsp 1.670.777-RS, Rel. Min. Og Fernandes, Segunda Turma, por maioria, julgado em 15\/10\/2019, DJe 03\/02\/2020<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><a>9.1. Situa\u00e7\u00e3o F\u00c1TICA.<\/a><\/h3>\n\n\n\n<p>Moetudo Ltda \u00e9 pessoa jur\u00eddica que beneficia cereais, ajuizou a\u00e7\u00e3o para reconhecimento do direito ao cr\u00e9dito presumido de PIS\/PASEP e Cofins.<\/p>\n\n\n\n<p>O ju\u00edzo de origem indeferiu sua pretens\u00e3o, assentando que ela N\u00c3O se encaixa no conceito de produtora a que as leis de reg\u00eancia se referem, de modo que n\u00e3o faz jus ao benef\u00edcio tribut\u00e1rio.<\/p>\n\n\n\n<p>Contudo, o Tribunal Regional Federal competente reformou a senten\u00e7a baseado no argumento de que o beneficiamento dos gr\u00e3os se enquadraria no conceito de produ\u00e7\u00e3o previsto no&nbsp; art. 8\u00ba da Lei n\u00ba 10.925\/04 c\/c o art. 56-A da Lei n\u00ba 12.350\/10, acrescido pela Lei n\u00ba 12.431\/11.<\/p>\n\n\n\n<p>O Fisco n\u00e3o gostou da decis\u00e3o e foi ao STJ buscar reverter o julgado.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><a>9.2. An\u00e1lise ESTRAT\u00c9GICA.<\/a><\/h3>\n\n\n\n<h4 class=\"wp-block-heading\">9.2.1.&nbsp;&nbsp;&nbsp;&nbsp; Cerealista tem direito ao cr\u00e9dito presumido de PIS\/PASEP previsto na lei n. 10.925\/2004?<\/h4>\n\n\n\n<p><strong><em><u>R:<\/u><\/em><\/strong> <strong>N\u00c3O.<\/strong><\/p>\n\n\n\n<p>A controv\u00e9rsia reside no conceito de produ\u00e7\u00e3o para fins de reconhecimento do direito aos cr\u00e9ditos presumidos de PIS\/PASEP e Cofins de que trata o art. 8\u00ba, \u00a7 1\u00ba, I, \u00a7 4\u00ba, I, da Lei n. 10.925\/2004.<\/p>\n\n\n\n<p><em>Segundo o pr\u00f3prio legislador, PRODU\u00c7\u00c3O \u00e9 a atividade que <u>modifica<\/u> os produtos animais ou vegetais, transformando-os em outros.<\/em><\/p>\n\n\n\n<p>As palavras de ordem aqui s\u00e3o MODIFICA\u00c7\u00c3O e TRANSFORMA\u00c7\u00c3O. O produtor \u00e9 aquele que modifica ou transforma uma coisa em outra.<\/p>\n\n\n\n<p>Assim, para fazer jus ao benef\u00edcio fiscal, a sociedade interessada deve produzir mercadorias, ou seja, deve realizar <strong><u>processo de industrializa\u00e7\u00e3o<\/u><\/strong> a partir de gr\u00e3os de soja, milho e trigo adquiridos de pessoa f\u00edsica, cooperado pessoa f\u00edsica ou cerealista, transformando-os em outros (v.g. \u00f3leo de soja, farelo de soja, leite de soja, \u00f3leo de trigo, farinha de trigo, p\u00e3es, massas, biscoitos, fub\u00e1, polenta etc).<\/p>\n\n\n\n<p><strong>PRODU\u00c7\u00c3O<\/strong> = MILHO, SOJA, TRIGO (recurso natural) \u00e0 \u00d3LEO, LEITE, FARINHA, P\u00c3O, MASSA, BISCOITO, FUB\u00c1, POLENTA (produto).<\/p>\n\n\n\n<p>Nesse sentido, <em>as atividades de limpeza, secagem, classifica\u00e7\u00e3o e armazenagem<\/em>N\u00c3O ocasionam transforma\u00e7\u00e3o do produto, enquadrando a sociedade na qualidade de mera cerealista e atraindo a veda\u00e7\u00e3o<strong> <\/strong>de aproveitamento do cr\u00e9dito discutido.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">9.2.2.&nbsp; Resultado final.<\/h4>\n\n\n\n<p>T\u00eam direito ao cr\u00e9dito presumido de PIS\/PASEP e Cofins as pessoas jur\u00eddicas, inclusive cooperativas, que produzam mercadorias por meio de processo de industrializa\u00e7\u00e3o de gr\u00e3os de soja, milho e trigo adquiridos de pessoa f\u00edsica, cerealista ou cooperado pessoa f\u00edsica. Por\u00e9m, os <strong>meros cerealistas <\/strong>N\u00c3O t\u00eam direito ao cr\u00e9dito presumido uma vez que a atividade por eles desempenhada n\u00e3o se enquadra no conceito de produ\u00e7\u00e3o previsto em lei.<\/p>\n\n\n\n<h1 class=\"wp-block-heading\"><a>D<\/a>IREITO PENAL<\/h1>\n\n\n\n<h2 class=\"wp-block-heading\">10. &nbsp;<a>Cabimento de Habeas Corpus para retificar registros pret\u00e9ritos<\/a><\/h2>\n\n\n\n<p><strong>HABEAS CORPUS<\/strong><\/p>\n\n\n\n<p>Demonstrada mera falta de t\u00e9cnica na senten\u00e7a, o habeas corpus pode ser deferido para nominar de forma correta os registros pret\u00e9ritos da paciente, doravante chamados de maus antecedentes, e n\u00e3o de conduta social, sem afastar, todavia, o dado desabonador que, concretamente, existe nos autos e justifica diferenciada individualiza\u00e7\u00e3o da pena.<\/p>\n\n\n\n<p>HC 501.144-SP, Rel. Min. Rogerio Schietti Cruz, Sexta Turma, por unanimidade, julgado em 10\/03\/2020, DJe 17\/03\/2020<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><a>10.1.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Situa\u00e7\u00e3o F\u00e1tica<\/a><\/h3>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; &nbsp;Josefina foi condenada a 3 anos e 4 meses de reclus\u00e3o em regime inicial <em>semiaberto<\/em> pelo crime de furto.<\/p>\n\n\n\n<p>Na hora de proferir a senten\u00e7a, a ju\u00edza considerou que Josefina contava com outras CINCO condena\u00e7\u00f5es definitivas por id\u00eantico crime, N\u00c3O valoradas como reincid\u00eancia, nem fracionadas para an\u00e1lise negativa de mais de uma circunst\u00e2ncia judicial (ju\u00edza para l\u00e1 de boazinha!).<\/p>\n\n\n\n<p>As inst\u00e2ncias ordin\u00e1rias recursais, contudo, classificaram os antecedentes como conduta social negativa. Est\u00e1 certo isso?<\/p>\n\n\n\n<p>A defesa entende que n\u00e3o, e que essa circunst\u00e2ncia judicial desabonadora deve ser afastada, de modo que a pena fique levinha&#8230;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><a>10.2.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; An\u00e1lise ESTRAT\u00c9GICA<\/a><a>.<\/a><\/h3>\n\n\n\n<h4 class=\"wp-block-heading\">10.2.1. Registros criminais antecedentes podem ser considerados como conduta social negativa?<\/h4>\n\n\n\n<p><strong><em><u>R:<\/u><\/em><\/strong> <strong>Nops!<\/strong><\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; A Terceira Se\u00e7\u00e3o j\u00e1 pacificou o entendimento de que: &#8220;eventuais <strong>condena\u00e7\u00f5es criminais do r\u00e9u transitadas em julgado<\/strong> e N\u00c3O utilizadas para caracterizar a <em>reincid\u00eancia<\/em> SOMENTE podem ser valoradas, na primeira fase da dosimetria, a t\u00edtulo de antecedentes criminais, N\u00c3O se admitindo sua utiliza\u00e7\u00e3o tamb\u00e9m para desvalorar a personalidade ou a conduta social do agente&#8221; (EREsp n. 1.688.077\/MS, Rel. Ministro Reynaldo Soares da Fonseca, 3\u00aa S., DJe 28\/8\/2019).<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; O v\u00edcio do ato apontado como coator se refere, t\u00e3o somente, ao incorreto T\u00cdTULO conferido \u00e0 vetorial do art. 59 do CP. Uma vez <strong><u>reconhecida a <em>atecnia<\/em> do Tribunal <em>a quo<\/em><\/u><\/strong> (ao considerar os registros como m\u00e1 conduta social), mas verificado que, de fato, a r\u00e9 ostenta v\u00e1rias condena\u00e7\u00f5es irrecorr\u00edveis \u2014 o que demanda mais rigorosa repress\u00e3o penal, para preven\u00e7\u00e3o e repress\u00e3o de sua conduta reiterada \u2014, o correto \u00e9 \u201c<em>CONCEDER<\/em>\u201d a ordem para <strong><u>CORRIGIR a denomina\u00e7\u00e3o errada da circunst\u00e2ncia judicial negativa<\/u><\/strong>.<\/p>\n\n\n\n<p><em>A dic\u00e7\u00e3o legal do art. 59 do CP <u>n\u00e3o<\/u> imp\u00f5e ao juiz a obriga\u00e7\u00e3o de intitular as circunst\u00e2ncias judiciais na senten\u00e7a.<\/em><\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Na tarefa individualizadora da reprimenda b\u00e1sica \u00e9 cogente, apenas, <strong>indicar as peculiaridades do caso concreto<\/strong> relacionadas aos vetores elencados pelo legislador.<\/p>\n\n\n\n<p>Se a senten\u00e7a simplesmente registrar a exist\u00eancia de v\u00e1rias condena\u00e7\u00f5es definitivas anteriores, <strong>SEM dar um nome espec\u00edfico<\/strong> para essa circunst\u00e2ncia, N\u00c3O haver\u00e1 v\u00edcio algum. Da mesma forma, se afirmar que o resultado \u00e9 mais gravoso do que o previsto no tipo penal, <em>sem chamar tal dado de consequ\u00eancias do crime<\/em>, estar\u00e1 justificado o acr\u00e9scimo da pena-base.<\/p>\n\n\n\n<p>Identificada apenas uma <em>atecnia<\/em>, <strong>N\u00c3O se pode desconsiderar o registro concreto feito pelo Juiz<\/strong> sentenciante da &#8220;pr\u00e1tica do mesmo crime de estelionato em outras a\u00e7\u00f5es penais&#8221;, de modo a punir a r\u00e9 da mesma forma que um criminoso ne\u00f3fito.<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; &nbsp;Se a defesa n\u00e3o instruiu a impetra\u00e7\u00e3o com certid\u00e3o comprobat\u00f3ria de que as anota\u00e7\u00f5es n\u00e3o existem, o correto \u00e9, t\u00e3o-somente, <strong>CORRIGIR o \u00fanico v\u00edcio verificado no <\/strong><strong>ato apontado como coator e consertar a classifica\u00e7\u00e3o err\u00f4nea da circunst\u00e2ncia judicial<\/strong>, de forma a dar-lhe o nome correto, consoante a classifica\u00e7\u00e3o jur\u00eddica dos vetores do art. 59 do CP.<\/p>\n\n\n\n<p>Apenas quando osantecedentes n\u00e3o existirem ou<strong> forem fracionados, para an\u00e1lise negativa, <\/strong><em>tamb\u00e9m, como marcadores da conduta social ou da personalidade<\/em>, \u00e9 poss\u00edvel reduzir a pena em habeas corpus, pois somente ent\u00e3o estar\u00e1 caracterizado v\u00edcio de fundamenta\u00e7\u00e3o e\/ou <em>bis in idem<\/em> na exaspera\u00e7\u00e3o da pena-base.<\/p>\n\n\n\n<h1 class=\"wp-block-heading\"><a>DIREITO PROCESSUAL PENAL<\/a><\/h1>\n\n\n\n<h2 class=\"wp-block-heading\"><a>11.&nbsp; Habeas Corpus concomitantemente ao recurso cab\u00edvel<\/a><\/h2>\n\n\n\n<p><strong>HABEAS CORPUS<\/strong><\/p>\n\n\n\n<p>O habeas corpus, quando impetrado de forma concomitante com o recurso cab\u00edvel contra o ato impugnado, ser\u00e1 admiss\u00edvel apenas se for destinado \u00e0 tutela direta da liberdade de locomo\u00e7\u00e3o ou se traduzir pedido diverso do objeto do recurso pr\u00f3prio e que reflita mediatamente na liberdade do paciente.<\/p>\n\n\n\n<p>HC 482.549-SP, Rel. Min. Rogerio Schietti Cruz, Terceira Se\u00e7\u00e3o, por maioria, julgado em 11\/03\/2020, DJe 03\/04\/2020<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><a>11.1.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Situa\u00e7\u00e3o F\u00c1TICA.<\/a><\/h3>\n\n\n\n<p>Josualdo foi condenado em primeira inst\u00e2ncia a uma pena de 5 anos e 10 meses e multa em regime inicial fechado. A defesa ingressou com o recurso de apela\u00e7\u00e3o e, concomitantemente, impetrou Habeas Corpus (com as mesmas teses), o qual deixou de ser conhecido pela exist\u00eancia de recurso espec\u00edfico pendente de julgamento no qual seria analisada a pretens\u00e3o defensiva.<\/p>\n\n\n\n<p>A defesa insiste que poderia, concomitantemente, impetrar HC e interpor o recurso cab\u00edvel.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><a>11.2.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; An\u00e1lise ESTRAT\u00c9GICA.<\/a><\/h3>\n\n\n\n<h4 class=\"wp-block-heading\">11.2.1. \u00c9 cab\u00edvel a impetra\u00e7\u00e3o de Habeas Corpus em conjunto ou concomitantemente com o recurso adequado?<\/h4>\n\n\n\n<p><strong><em><u>R:<\/u><\/em><\/strong> <strong>Apenas excepcionalmente.<\/strong><\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; A exist\u00eancia de um complexo sistema recursal no processo penal brasileiro permite \u00e0 parte prejudicada por decis\u00e3o judicial submeter ao \u00f3rg\u00e3o colegiado competente a revis\u00e3o do ato jurisdicional, na forma e no prazo previstos em lei.<\/p>\n\n\n\n<p>Ainda assim, eventual manejo de <em>habeas corpus<\/em>, a\u00e7\u00e3o constitucional voltada \u00e0 prote\u00e7\u00e3o da liberdade humana, constitui estrat\u00e9gia defensiva v\u00e1lida, sopesadas as VANTAGENS mas tamb\u00e9m os \u00f4nus de tal op\u00e7\u00e3o.<\/p>\n\n\n\n<p><em>A tutela constitucional e legal da liberdade humana JUSTIFICA algum temperamento dos rigores formais inerentes aos recursos em geral.<\/em><\/p>\n\n\n\n<p>Contudo, N\u00c3O se dispensa a racionalidade no uso dos instrumentos postos \u00e0 disposi\u00e7\u00e3o do acusadoao longo da persecu\u00e7\u00e3o penal, dada a <strong>necessidade de tamb\u00e9m preservar a FUNCIONALIDADE do sistema de justi\u00e7a<\/strong> criminal, cujo <em>poder de julgar<\/em><em> de maneira organizada, acurada e correta,<\/em> permeado pelas limita\u00e7\u00f5es materiais e humanas dos \u00f3rg\u00e3os de jurisdi\u00e7\u00e3o, v\u00ea-se comprometido \u2014em preju\u00edzo da sociedade e dos jurisdicionados em geral \u2014 pelo concomitante emprego de DOIS meios de impugna\u00e7\u00e3o com igual pretens\u00e3o.<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Sob essa perspectiva, <em>a interposi\u00e7\u00e3o do recurso cab\u00edvel contra o ato impugnado e a contempor\u00e2nea impetra\u00e7\u00e3o de habeas corpus para <u>igual pretens\u00e3o<\/u><\/em> somente permitir\u00e3o o exame do <em>writ<\/em> se for este destinado \u00e0 tutela direta da liberdade de locomo\u00e7\u00e3o ou se traduzir pedido DIVERSO em rela\u00e7\u00e3o ao que \u00e9 objeto do recurso pr\u00f3prio e que reflita mediatamente na <strong>liberdade<\/strong> do paciente.<\/p>\n\n\n\n<p>A impetra\u00e7\u00e3o de HC e a interposi\u00e7\u00e3o de recurso, ao mesmo tempo, SOMENTE \u00e9 admitida: <strong>(a)<\/strong> tutela direta da liberdade de locomo\u00e7\u00e3o; <strong>(b)<\/strong> traduzir pedido diverso em rela\u00e7\u00e3o ao que \u00e9 objeto do recurso pr\u00f3prio.<\/p>\n\n\n\n<p>Nas demais hip\u00f3teses, o <em>habeas corpus<\/em> <strong><u>N\u00c3O deve ser admitido<\/u><\/strong> e o exame das quest\u00f5es id\u00eanticas deve ser <em>reservado ao recurso <\/em>previsto para a hip\u00f3tese, ainda que a mat\u00e9ria discutida resvale, por via transversa, na liberdade individual.<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; A solu\u00e7\u00e3o deriva da percep\u00e7\u00e3o de que o recurso de apela\u00e7\u00e3o det\u00e9m efeito devolutivo amplo e graus de cogni\u00e7\u00e3o (horizontal e vertical) <em>mais amplo e aprofundado<\/em>, de modo a permitir que o tribunala quem se dirige a impugna\u00e7\u00e3o <strong>examine, mais acuradamente, todos os aspectos relevantes <\/strong>que subjazem na a\u00e7\u00e3o penal.<\/p>\n\n\n\n<p>Assim, em princ\u00edpio, a apela\u00e7\u00e3o \u00e9 a via processual mais adequada para a impugna\u00e7\u00e3o de senten\u00e7a condenat\u00f3ria recorr\u00edvel, pois \u00e9 esse o recurso que <strong>devolve ao tribunal o conhecimento amplo de toda a mat\u00e9ria versada nos autos<\/strong>, permitindo a reaprecia\u00e7\u00e3o de fatos e de provas, com todas as suas nuan\u00e7as, sem a limita\u00e7\u00e3o cognitiva da via mandamental.&nbsp;<\/p>\n\n\n\n<p>O mesmo racioc\u00ednio \u00e9 V\u00c1LIDO para a interposi\u00e7\u00e3o de <em>habeas corpus<\/em> juntamente com o manejo de <strong>agravo em execu\u00e7\u00e3o, recurso em sentido estrito, recurso especial e revis\u00e3o criminal<\/strong>.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">11.2.2.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Resultado final.<\/h4>\n\n\n\n<p>O <em>habeas corpus<\/em>,quando impetrado de forma concomitante com o recurso cab\u00edvel contra o ato impugnado, ser\u00e1 admiss\u00edvel apenas se for destinado \u00e0 tutela direta da liberdade de locomo\u00e7\u00e3o ou se traduzir pedido diverso do objeto do recurso pr\u00f3prio e que reflita mediatamente na liberdade do paciente.<\/p>\n\n\n\n<div class=\"wp-block-file\"><a href=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/07\/06231642\/STJ-669.pdf\">STJ-669<\/a><a href=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/07\/06231642\/STJ-669.pdf\" class=\"wp-block-file__button\" download>Baixar<\/a><\/div>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Para n\u00e3o deixar passar nada, estamos colocando em dia os informativos de 2020 (todos eles!). E aqui vai o informativo 669 do STJ Comentad\u00edssimo. DOWNLOAD do PDF AQUI! DIREITO CONSTITUCIONAL. 2 1.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Reclama\u00e7\u00e3o para controle de aplica\u00e7\u00e3o de entendimento firmado pelo STJ. 2 1.1.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Situa\u00e7\u00e3o F\u00c1TICA. 2 1.2.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; An\u00e1lise ESTRAT\u00c9GICA. 3 DIREITO ADMINISTRATIVO&#8230; 5 2.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; [&hellip;]<\/p>\n","protected":false},"author":833,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"post_tipo":"article","footnotes":""},"categories":[1],"tags":[],"tax_estado":[],"class_list":["post-538575","post","type-post","status-publish","format-standard","hentry","category-cursos-e-concursos"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.2 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Informativo STJ 669 Comentado<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/informativo-stj-669-comentado\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Informativo STJ 669 Comentado\" \/>\n<meta property=\"og:description\" content=\"Para n\u00e3o deixar passar nada, estamos colocando em dia os informativos de 2020 (todos eles!). E aqui vai o informativo 669 do STJ Comentad\u00edssimo. DOWNLOAD do PDF AQUI! DIREITO CONSTITUCIONAL. 2 1.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Reclama\u00e7\u00e3o para controle de aplica\u00e7\u00e3o de entendimento firmado pelo STJ. 2 1.1.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Situa\u00e7\u00e3o F\u00c1TICA. 2 1.2.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; An\u00e1lise ESTRAT\u00c9GICA. 3 DIREITO ADMINISTRATIVO&#8230; 5 2.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/informativo-stj-669-comentado\/\" \/>\n<meta property=\"og:site_name\" content=\"Estrat\u00e9gia Concursos\" \/>\n<meta property=\"article:published_time\" content=\"2020-07-07T02:17:20+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-07-07T02:17:22+00:00\" \/>\n<meta name=\"author\" content=\"Jean Vilbert\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:site\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jean Vilbert\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"35 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/informativo-stj-669-comentado\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/informativo-stj-669-comentado\/\"},\"author\":{\"name\":\"Jean Vilbert\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/475a0922f10cff0d1bc8bfecde05f999\"},\"headline\":\"Informativo STJ 669 Comentado\",\"datePublished\":\"2020-07-07T02:17:20+00:00\",\"dateModified\":\"2020-07-07T02:17:22+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/informativo-stj-669-comentado\/\"},\"wordCount\":6994,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"articleSection\":[\"Concursos P\u00fablicos\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/informativo-stj-669-comentado\/#respond\"]}],\"copyrightYear\":\"2020\",\"copyrightHolder\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/informativo-stj-669-comentado\/\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/informativo-stj-669-comentado\/\",\"name\":\"Informativo STJ 669 Comentado\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\"},\"datePublished\":\"2020-07-07T02:17:20+00:00\",\"dateModified\":\"2020-07-07T02:17:22+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/informativo-stj-669-comentado\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/informativo-stj-669-comentado\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/informativo-stj-669-comentado\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Informativo STJ 669 Comentado\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"name\":\"Estrat\u00e9gia Concursos\",\"description\":\"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.\",\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\",\"name\":\"Estrat\u00e9gia Concursos\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"width\":230,\"height\":60,\"caption\":\"Estrat\u00e9gia Concursos\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/EstratConcursos\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/475a0922f10cff0d1bc8bfecde05f999\",\"name\":\"Jean Vilbert\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/1667694e4ebdd32feeac9ea2794de3f0470b5c55c6198181ab0b0c333b121921?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/1667694e4ebdd32feeac9ea2794de3f0470b5c55c6198181ab0b0c333b121921?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/1667694e4ebdd32feeac9ea2794de3f0470b5c55c6198181ab0b0c333b121921?s=96&d=mm&r=g\",\"caption\":\"Jean Vilbert\"},\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/jeanvilbertgmail-com\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Informativo STJ 669 Comentado","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.estrategiaconcursos.com.br\/blog\/informativo-stj-669-comentado\/","og_locale":"pt_BR","og_type":"article","og_title":"Informativo STJ 669 Comentado","og_description":"Para n\u00e3o deixar passar nada, estamos colocando em dia os informativos de 2020 (todos eles!). E aqui vai o informativo 669 do STJ Comentad\u00edssimo. DOWNLOAD do PDF AQUI! DIREITO CONSTITUCIONAL. 2 1.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Reclama\u00e7\u00e3o para controle de aplica\u00e7\u00e3o de entendimento firmado pelo STJ. 2 1.1.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Situa\u00e7\u00e3o F\u00c1TICA. 2 1.2.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; An\u00e1lise ESTRAT\u00c9GICA. 3 DIREITO ADMINISTRATIVO&#8230; 5 2.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; [&hellip;]","og_url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/informativo-stj-669-comentado\/","og_site_name":"Estrat\u00e9gia Concursos","article_published_time":"2020-07-07T02:17:20+00:00","article_modified_time":"2020-07-07T02:17:22+00:00","author":"Jean Vilbert","twitter_card":"summary_large_image","twitter_creator":"@EstratConcursos","twitter_site":"@EstratConcursos","twitter_misc":{"Escrito por":"Jean Vilbert","Est. tempo de leitura":"35 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/informativo-stj-669-comentado\/#article","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/informativo-stj-669-comentado\/"},"author":{"name":"Jean Vilbert","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/475a0922f10cff0d1bc8bfecde05f999"},"headline":"Informativo STJ 669 Comentado","datePublished":"2020-07-07T02:17:20+00:00","dateModified":"2020-07-07T02:17:22+00:00","mainEntityOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/informativo-stj-669-comentado\/"},"wordCount":6994,"commentCount":0,"publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"articleSection":["Concursos P\u00fablicos"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/informativo-stj-669-comentado\/#respond"]}],"copyrightYear":"2020","copyrightHolder":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/informativo-stj-669-comentado\/","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/informativo-stj-669-comentado\/","name":"Informativo STJ 669 Comentado","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website"},"datePublished":"2020-07-07T02:17:20+00:00","dateModified":"2020-07-07T02:17:22+00:00","breadcrumb":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/informativo-stj-669-comentado\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/informativo-stj-669-comentado\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/informativo-stj-669-comentado\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.estrategiaconcursos.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Informativo STJ 669 Comentado"}]},{"@type":"WebSite","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","name":"Estrat\u00e9gia Concursos","description":"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.","publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization","name":"Estrat\u00e9gia Concursos","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","width":230,"height":60,"caption":"Estrat\u00e9gia Concursos"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/EstratConcursos"]},{"@type":"Person","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/475a0922f10cff0d1bc8bfecde05f999","name":"Jean Vilbert","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/1667694e4ebdd32feeac9ea2794de3f0470b5c55c6198181ab0b0c333b121921?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/1667694e4ebdd32feeac9ea2794de3f0470b5c55c6198181ab0b0c333b121921?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1667694e4ebdd32feeac9ea2794de3f0470b5c55c6198181ab0b0c333b121921?s=96&d=mm&r=g","caption":"Jean Vilbert"},"url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/jeanvilbertgmail-com\/"}]}},"_links":{"self":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/538575","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/users\/833"}],"replies":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/comments?post=538575"}],"version-history":[{"count":1,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/538575\/revisions"}],"predecessor-version":[{"id":538581,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/538575\/revisions\/538581"}],"wp:attachment":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media?parent=538575"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/categories?post=538575"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tags?post=538575"},{"taxonomy":"tax_estado","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tax_estado?post=538575"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}