{"id":53617,"date":"2016-12-01T07:25:54","date_gmt":"2016-12-01T10:25:54","guid":{"rendered":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?p=53617"},"modified":"2018-07-30T12:59:16","modified_gmt":"2018-07-30T15:59:16","slug":"aprovado-reajuste-para-servidores-da-pf-e-prf","status":"publish","type":"post","link":"https:\/\/www.estrategiaconcursos.com.br\/blog\/aprovado-reajuste-para-servidores-da-pf-e-prf\/","title":{"rendered":"Carreira ainda mais atrativa: Publicada a Lei do reajuste para servidores da PF e PRF. Remunera\u00e7\u00e3o de delegados e peritos poder\u00e1 ultrapassar R$30 mil! Saiba mais!"},"content":{"rendered":"<p style=\"text-align: justify;\"><em><span style=\"color: #000000;\"><strong><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-53618 size-full\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2016\/10\/27163945\/pf.jpg\" alt=\"reajuste PF e PRF\" width=\"275\" height=\"183\" \/>Carreira ainda mais atrativa: Publicada a Lei do\u00a0reajuste para servidores da PF e PRF e outros. Remunera\u00e7\u00e3o de delegados e peritos poder\u00e1 ultrapassar R$30 mil! Saiba mais!<\/strong><\/span><\/em><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Foi publicada hoje, 15 de dezembro, a Lei n\u00ba 13.371\/16\u00a0que prev\u00ea reajuste para os servidores da Pol\u00edcia Federal (PF), Pol\u00edcia Rodovi\u00e1ria Federal (PRF), entre outras categorias.\u00a0<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">A Lei prev\u00ea\u00a0que haja reajustes de at\u00e9 37% a serem pagos em tr\u00eas parcelas, at\u00e9 2019. Dessa forma,\u00a0os delegados da PF e os peritos criminais federais, que ganham hoje sal\u00e1rio inicial de R$ 16.830 em 3\u00aa classe, passar\u00e3o a ter remunera\u00e7\u00e3o de R$ 21.644 em janeiro de 2017, chegando a R$ 23.000 em 2019. Ap\u00f3s progress\u00e3o na carreira, o sal\u00e1rio passar\u00e1 dos atuais R$ 22.805 para R$ 28.262 no in\u00edcio do pr\u00f3ximo ano e ultrapassar\u00e1\u00a0R$30 mil em tr\u00eas anos.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">O reajuste contemplou ainda os\u00a0peritos federais agr\u00e1rios e os servidores do plano especial de cargos do Departamento Nacional de Infraestrutura de Transportes (DNIT).\u00a0<\/span><\/p>\n<h3 style=\"text-align: justify;\"><strong><span style=\"color: #000000;\">Subs\u00eddios das carreiras com o Reajuste<\/span><\/strong><\/h3>\n<h2><span style=\"color: #000000;\"><strong>Pol\u00edcia Federal:<\/strong><\/span><\/h2>\n<ul>\n<li><span style=\"color: #000000;\"> Cargos de Delegado de Pol\u00edcia Federal e de Perito Criminal Federal<\/span><\/li>\n<\/ul>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-56576 size-full\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2016\/10\/01072419\/concurso-tjpr.png\" alt=\"concurso pf\" width=\"750\" height=\"209\" srcset=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2016\/10\/01072419\/concurso-tjpr.png 750w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2016\/10\/01072419\/concurso-tjpr.png 300w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2016\/10\/01072419\/concurso-tjpr.png 500w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/><\/p>\n<ul>\n<li style=\"text-align: justify;\"><span style=\"color: #000000;\">Cargos de Agente de Pol\u00edcia Federal, de Escriv\u00e3o de Pol\u00edcia Federal e de Papiloscopista Policial Federal<\/span><\/li>\n<\/ul>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-56577 size-full\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2016\/10\/01072550\/concurso-tjpr1.png\" alt=\"concurso pf\" width=\"744\" height=\"322\" srcset=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2016\/10\/01072550\/concurso-tjpr1.png 744w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2016\/10\/01072550\/concurso-tjpr1.png 300w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2016\/10\/01072550\/concurso-tjpr1.png 500w\" sizes=\"auto, (max-width: 744px) 100vw, 744px\" \/><\/p>\n<h2><span style=\"color: #000000;\">Pol\u00edcia Rodovi\u00e1ria Federal:<\/span><\/h2>\n<ul>\n<li><span style=\"color: #000000;\">Policial Rodovi\u00e1rio Federal<\/span><\/li>\n<\/ul>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-56578\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2016\/10\/01072825\/concurso-tjpr2.png\" alt=\"concurso prf\" width=\"751\" height=\"547\" srcset=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2016\/10\/01072825\/concurso-tjpr2.png 751w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2016\/10\/01072825\/concurso-tjpr2.png 300w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2016\/10\/01072825\/concurso-tjpr2.png 412w\" sizes=\"auto, (max-width: 751px) 100vw, 751px\" \/><\/p>\n<h3 style=\"text-align: justify;\"><strong><span style=\"color: #000000;\">PR\u00d3XIMO CONCURSO PRF<\/span><\/strong><\/h3>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Os andamentos\u00a0para a abertura de um novo processo seletivo da Pol\u00edcia Rodovi\u00e1ria Federal (<a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-prf-2\/\">concurso PRF<\/a>) seguem em pauta.\u00a0<\/span><span style=\"color: #000000;\">No dia 22 de setembro deste ano\u00a0foi divulgado o extrato de dispensa de licita\u00e7\u00e3o para a contra\u00e7\u00e3o da empresa Connect On Cursos e Eventos EIRELI \u2013 ME,\u00a0para\u00a0\u00a0realizar, para seus servidores, o curso interno\u00a0\u201cCurso Concurso P\u00fablico Teoria e Pr\u00e1tica: Seguran\u00e7a e Efici\u00eancia no Planejamento, Realiza\u00e7\u00e3o e Controle\u201d.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Al\u00e9m disso, a PRF j\u00e1 constituiu um Grupo de Trabalho para elabora\u00e7\u00e3o de proposta de novo Edital do Concurso P\u00fablico para o provimento de cargos de Policial Rodovi\u00e1rio Federal.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Formado por servidores da PRF, o Grupo de Trabalho tem como objetivo analisar os editais de concursos anteriores, realizar levantamento de \u00f3bices \u00e0 realiza\u00e7\u00e3o de etapas de concursos p\u00fablicos, mapear as vulnerabilidades apontadas nas diversas a\u00e7\u00f5es judiciais com objetivo de efetuar ajustes e aprimorar procedimentos relativos ao certame, al\u00e9m de realizar um estudo sobre o atual quadro de pessoal e suas necessidades.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">O Grupo dever\u00e1 apresentar como produto final a proposta (minuta) de edital e dever\u00e1 concluir suas atividades at\u00e9 30 de novembro de 2016, podendo o prazo ser prorrogado por mais 30 dias.<\/span><\/p>\n<h3 style=\"text-align: justify;\"><span style=\"color: #000000;\"><strong>PR\u00d3XIMO CONCURSO PF<\/strong><\/span><\/h3>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Solicitado em maio de 2015, o novo <a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-pf\/\">concurso PF<\/a> segue sem novidades desde junho deste ano, quando\u00a0os processos que tratam da consulta de verba para realiza\u00e7\u00e3o do\u00a0concurso Policia Federal voltaram a tramitar no Minist\u00e9rio do Planejamento, passando pela\u00a0Coordena\u00e7\u00e3o Geral de Carreiras, Concursos e Desenvolvimento de Pessoas (SEGRT) e Coordena\u00e7\u00e3o Administrativa de Suporte T\u00e9cnico (Coast).<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Para o concurso PF foram solicitadas\u00a0558 vagas: 491 para delegado e 67 para perito. Para concorrer \u00e0s vagas de perito \u00e9 necess\u00e1rio curso superior completo, em \u00e1reas espec\u00edficas. No \u00faltimo concurso as \u00e1reas contempladas foram ci\u00eancias cont\u00e1beis ou econ\u00f4micas, engenharia em diversas especialidades, ci\u00eancias da computa\u00e7\u00e3o, geologia, qu\u00edmica, biomedicina, medicina, odontologia e farm\u00e1cia. J\u00e1 para o cargo de delegado \u00e9 necess\u00e1ria forma\u00e7\u00e3o em direito, com pelo menos tr\u00eas anos de pr\u00e1tica jur\u00eddica ou policial, comprovadas na data da posse. A remunera\u00e7\u00e3o \u00e9 de R$ 16.830,85 e carga hor\u00e1ria de 40 horas semanais.<\/span><\/p>\n<p style=\"text-align: justify;\"><strong><span style=\"color: #000000;\">O Estrat\u00e9gia Concursos j\u00e1 lan\u00e7ou cursos para estes concursos. Comece j\u00e1 a se preparar e saia na frente:<\/span><\/strong><\/p>\n<p><a href=\"https:\/\/www.estrategiaconcursos.com.br\/cursosPorConcurso\/policia-federal-agente-141\/\" target=\"_blank\" rel=\"noopener\">CURSOS AGENTE PF<\/a><\/p>\n<p><a href=\"https:\/\/www.estrategiaconcursos.com.br\/cursosPorConcurso\/policia-federal-delegado-79\/\" target=\"_blank\" rel=\"noopener\">CURSOS DELEGADO PF<\/a><\/p>\n<p><a href=\"https:\/\/www.estrategiaconcursos.com.br\/cursosPorConcurso\/policia-federal-perito-80\/\" target=\"_blank\" rel=\"noopener\">CURSOS PERITO PF<\/a><\/p>\n<p><a href=\"https:\/\/www.estrategiaconcursos.com.br\/cursosPorConcurso\/policia-federal-escrivao-27\/\" target=\"_blank\" rel=\"noopener\">CURSOS ESCRIV\u00c3O PF<\/a><\/p>\n<p><a href=\"https:\/\/www.estrategiaconcursos.com.br\/cursosPorConcurso\/policia-federal-agente-administrativo-nivel-medio\/\" target=\"_blank\" rel=\"noopener\">CURSOS AGENTE ADMINISTRATIVO PF<\/a><\/p>\n<p><a href=\"https:\/\/www.estrategiaconcursos.com.br\/cursosPorConcurso\/prf-policial-rodoviario-federal\/\" target=\"_blank\" rel=\"noopener\">CURSOS POLICIAL RODOVI\u00c1RIO<\/a><\/p>\n<p><a href=\"https:\/\/www.estrategiaconcursos.com.br\/cursosPorConcurso\/prf-policia-rodoviaria-federal-agente-administrativo-20\/\" target=\"_blank\" rel=\"noopener\">CURSOS AGENTE ADMINISTRATIVO PRF<\/a><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Assessoria de Comunica\u00e7\u00e3o<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">comunicacao@estrategiaconcursos.com.br<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Carreira ainda mais atrativa: Publicada a Lei do\u00a0reajuste para servidores da PF e PRF e outros. Remunera\u00e7\u00e3o de delegados e peritos poder\u00e1 ultrapassar R$30 mil! Saiba mais! Foi publicada hoje, 15 de dezembro, a Lei n\u00ba 13.371\/16\u00a0que prev\u00ea reajuste para os servidores da Pol\u00edcia Federal (PF), Pol\u00edcia Rodovi\u00e1ria Federal (PRF), entre outras categorias.\u00a0 A Lei [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":53619,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"post_tipo":"news","footnotes":""},"categories":[1,1988],"tags":[500,1396],"tax_estado":[],"class_list":["post-53617","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cursos-e-concursos","category-policia","tag-policia-federal","tag-policia-rodoviaria-federal"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.2 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Aprovado reajuste de 37% para servidores da PF e PRF<\/title>\n<meta name=\"description\" content=\"Com o reajuste, o sal\u00e1rio de delegados e peritos da PF passar\u00e1 dos atuais R$22.805 para R$28.262 no in\u00edcio do pr\u00f3ximo ano e ultrapassar\u00e1 R$30mil at\u00e9 2019..\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/aprovado-reajuste-para-servidores-da-pf-e-prf\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Carreira ainda mais atrativa: Publicada a Lei do reajuste para servidores da PF e PRF. Remunera\u00e7\u00e3o de delegados e peritos poder\u00e1 ultrapassar R$30 mil! Saiba mais!\" \/>\n<meta property=\"og:description\" content=\"Com o reajuste, o sal\u00e1rio de delegados e peritos da PF passar\u00e1 dos atuais R$22.805 para R$28.262 no in\u00edcio do pr\u00f3ximo ano e ultrapassar\u00e1 R$30mil at\u00e9 2019..\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/aprovado-reajuste-para-servidores-da-pf-e-prf\/\" \/>\n<meta property=\"og:site_name\" content=\"Estrat\u00e9gia Concursos\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/EstrategiaConcursos\" \/>\n<meta property=\"article:published_time\" content=\"2016-12-01T10:25:54+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-07-30T15:59:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2016\/10\/27164012\/comissao-aprova-reajuste-de-37-para-policia-federal-prf-e-dnit.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"627\" \/>\n\t<meta property=\"og:image:height\" content=\"410\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Coordena\u00e7\u00e3o\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:site\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Coordena\u00e7\u00e3o\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/aprovado-reajuste-para-servidores-da-pf-e-prf\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/aprovado-reajuste-para-servidores-da-pf-e-prf\/\"},\"author\":{\"name\":\"Coordena\u00e7\u00e3o\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/b4a388c97673c5f483d72185668afa1f\"},\"headline\":\"Carreira ainda mais atrativa: Publicada a Lei do reajuste para servidores da PF e PRF. Remunera\u00e7\u00e3o de delegados e peritos poder\u00e1 ultrapassar R$30 mil! Saiba mais!\",\"datePublished\":\"2016-12-01T10:25:54+00:00\",\"dateModified\":\"2018-07-30T15:59:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/aprovado-reajuste-para-servidores-da-pf-e-prf\/\"},\"wordCount\":667,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/aprovado-reajuste-para-servidores-da-pf-e-prf\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2016\/10\/27164012\/comissao-aprova-reajuste-de-37-para-policia-federal-prf-e-dnit.jpg\",\"keywords\":[\"Policia Federal\",\"Pol\u00edcia Rodovi\u00e1ria Federal\"],\"articleSection\":[\"Concursos P\u00fablicos\",\"Policial (Agente, Escriv\u00e3o e Investigador)\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/aprovado-reajuste-para-servidores-da-pf-e-prf\/#respond\"]}],\"copyrightYear\":\"2016\",\"copyrightHolder\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/aprovado-reajuste-para-servidores-da-pf-e-prf\/\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/aprovado-reajuste-para-servidores-da-pf-e-prf\/\",\"name\":\"Aprovado reajuste de 37% para servidores da PF e PRF\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/aprovado-reajuste-para-servidores-da-pf-e-prf\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/aprovado-reajuste-para-servidores-da-pf-e-prf\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2016\/10\/27164012\/comissao-aprova-reajuste-de-37-para-policia-federal-prf-e-dnit.jpg\",\"datePublished\":\"2016-12-01T10:25:54+00:00\",\"dateModified\":\"2018-07-30T15:59:16+00:00\",\"description\":\"Com o reajuste, o sal\u00e1rio de delegados e peritos da PF passar\u00e1 dos atuais R$22.805 para R$28.262 no in\u00edcio do pr\u00f3ximo ano e ultrapassar\u00e1 R$30mil at\u00e9 2019..\",\"breadcrumb\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/aprovado-reajuste-para-servidores-da-pf-e-prf\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/aprovado-reajuste-para-servidores-da-pf-e-prf\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/aprovado-reajuste-para-servidores-da-pf-e-prf\/#primaryimage\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2016\/10\/27164012\/comissao-aprova-reajuste-de-37-para-policia-federal-prf-e-dnit.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2016\/10\/27164012\/comissao-aprova-reajuste-de-37-para-policia-federal-prf-e-dnit.jpg\",\"width\":627,\"height\":410},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/aprovado-reajuste-para-servidores-da-pf-e-prf\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Carreira ainda mais atrativa: Publicada a Lei do reajuste para servidores da PF e PRF. Remunera\u00e7\u00e3o de delegados e peritos poder\u00e1 ultrapassar R$30 mil! Saiba mais!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"name\":\"Estrat\u00e9gia Concursos\",\"description\":\"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.\",\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\",\"name\":\"Estrat\u00e9gia Concursos\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"width\":230,\"height\":60,\"caption\":\"Estrat\u00e9gia Concursos\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/EstratConcursos\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/b4a388c97673c5f483d72185668afa1f\",\"name\":\"Coordena\u00e7\u00e3o\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/b720319e4c9a967eb58678d110f4fe35452fc5d5f97b202bac7b8acceb18c6ad?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/b720319e4c9a967eb58678d110f4fe35452fc5d5f97b202bac7b8acceb18c6ad?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/b720319e4c9a967eb58678d110f4fe35452fc5d5f97b202bac7b8acceb18c6ad?s=96&d=mm&r=g\",\"caption\":\"Coordena\u00e7\u00e3o\"},\"sameAs\":[\"https:\/\/www.facebook.com\/EstrategiaConcursos\",\"https:\/\/x.com\/EstratConcursos\"],\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/estrategia2013\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Aprovado reajuste de 37% para servidores da PF e PRF","description":"Com o reajuste, o sal\u00e1rio de delegados e peritos da PF passar\u00e1 dos atuais R$22.805 para R$28.262 no in\u00edcio do pr\u00f3ximo ano e ultrapassar\u00e1 R$30mil at\u00e9 2019..","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.estrategiaconcursos.com.br\/blog\/aprovado-reajuste-para-servidores-da-pf-e-prf\/","og_locale":"pt_BR","og_type":"article","og_title":"Carreira ainda mais atrativa: Publicada a Lei do reajuste para servidores da PF e PRF. Remunera\u00e7\u00e3o de delegados e peritos poder\u00e1 ultrapassar R$30 mil! Saiba mais!","og_description":"Com o reajuste, o sal\u00e1rio de delegados e peritos da PF passar\u00e1 dos atuais R$22.805 para R$28.262 no in\u00edcio do pr\u00f3ximo ano e ultrapassar\u00e1 R$30mil at\u00e9 2019..","og_url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/aprovado-reajuste-para-servidores-da-pf-e-prf\/","og_site_name":"Estrat\u00e9gia Concursos","article_author":"https:\/\/www.facebook.com\/EstrategiaConcursos","article_published_time":"2016-12-01T10:25:54+00:00","article_modified_time":"2018-07-30T15:59:16+00:00","og_image":[{"width":627,"height":410,"url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2016\/10\/27164012\/comissao-aprova-reajuste-de-37-para-policia-federal-prf-e-dnit.jpg","type":"image\/jpeg"}],"author":"Coordena\u00e7\u00e3o","twitter_card":"summary_large_image","twitter_creator":"@EstratConcursos","twitter_site":"@EstratConcursos","twitter_misc":{"Escrito por":"Coordena\u00e7\u00e3o","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/aprovado-reajuste-para-servidores-da-pf-e-prf\/#article","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/aprovado-reajuste-para-servidores-da-pf-e-prf\/"},"author":{"name":"Coordena\u00e7\u00e3o","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/b4a388c97673c5f483d72185668afa1f"},"headline":"Carreira ainda mais atrativa: Publicada a Lei do reajuste para servidores da PF e PRF. Remunera\u00e7\u00e3o de delegados e peritos poder\u00e1 ultrapassar R$30 mil! Saiba mais!","datePublished":"2016-12-01T10:25:54+00:00","dateModified":"2018-07-30T15:59:16+00:00","mainEntityOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/aprovado-reajuste-para-servidores-da-pf-e-prf\/"},"wordCount":667,"commentCount":0,"publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/aprovado-reajuste-para-servidores-da-pf-e-prf\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2016\/10\/27164012\/comissao-aprova-reajuste-de-37-para-policia-federal-prf-e-dnit.jpg","keywords":["Policia Federal","Pol\u00edcia Rodovi\u00e1ria Federal"],"articleSection":["Concursos P\u00fablicos","Policial (Agente, Escriv\u00e3o e Investigador)"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/aprovado-reajuste-para-servidores-da-pf-e-prf\/#respond"]}],"copyrightYear":"2016","copyrightHolder":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/aprovado-reajuste-para-servidores-da-pf-e-prf\/","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/aprovado-reajuste-para-servidores-da-pf-e-prf\/","name":"Aprovado reajuste de 37% para servidores da PF e PRF","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/aprovado-reajuste-para-servidores-da-pf-e-prf\/#primaryimage"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/aprovado-reajuste-para-servidores-da-pf-e-prf\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2016\/10\/27164012\/comissao-aprova-reajuste-de-37-para-policia-federal-prf-e-dnit.jpg","datePublished":"2016-12-01T10:25:54+00:00","dateModified":"2018-07-30T15:59:16+00:00","description":"Com o reajuste, o sal\u00e1rio de delegados e peritos da PF passar\u00e1 dos atuais R$22.805 para R$28.262 no in\u00edcio do pr\u00f3ximo ano e ultrapassar\u00e1 R$30mil at\u00e9 2019..","breadcrumb":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/aprovado-reajuste-para-servidores-da-pf-e-prf\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/aprovado-reajuste-para-servidores-da-pf-e-prf\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/aprovado-reajuste-para-servidores-da-pf-e-prf\/#primaryimage","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2016\/10\/27164012\/comissao-aprova-reajuste-de-37-para-policia-federal-prf-e-dnit.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2016\/10\/27164012\/comissao-aprova-reajuste-de-37-para-policia-federal-prf-e-dnit.jpg","width":627,"height":410},{"@type":"BreadcrumbList","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/aprovado-reajuste-para-servidores-da-pf-e-prf\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.estrategiaconcursos.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Carreira ainda mais atrativa: Publicada a Lei do reajuste para servidores da PF e PRF. Remunera\u00e7\u00e3o de delegados e peritos poder\u00e1 ultrapassar R$30 mil! Saiba mais!"}]},{"@type":"WebSite","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","name":"Estrat\u00e9gia Concursos","description":"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.","publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization","name":"Estrat\u00e9gia Concursos","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","width":230,"height":60,"caption":"Estrat\u00e9gia Concursos"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/EstratConcursos"]},{"@type":"Person","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/b4a388c97673c5f483d72185668afa1f","name":"Coordena\u00e7\u00e3o","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/b720319e4c9a967eb58678d110f4fe35452fc5d5f97b202bac7b8acceb18c6ad?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b720319e4c9a967eb58678d110f4fe35452fc5d5f97b202bac7b8acceb18c6ad?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b720319e4c9a967eb58678d110f4fe35452fc5d5f97b202bac7b8acceb18c6ad?s=96&d=mm&r=g","caption":"Coordena\u00e7\u00e3o"},"sameAs":["https:\/\/www.facebook.com\/EstrategiaConcursos","https:\/\/x.com\/EstratConcursos"],"url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/estrategia2013\/"}]}},"_links":{"self":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/53617","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/comments?post=53617"}],"version-history":[{"count":9,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/53617\/revisions"}],"predecessor-version":[{"id":133658,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/53617\/revisions\/133658"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media\/53619"}],"wp:attachment":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media?parent=53617"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/categories?post=53617"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tags?post=53617"},{"taxonomy":"tax_estado","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tax_estado?post=53617"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}