{"id":526754,"date":"2020-07-01T16:10:00","date_gmt":"2020-07-01T19:10:00","guid":{"rendered":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?p=526754"},"modified":"2020-06-23T16:12:38","modified_gmt":"2020-06-23T19:12:38","slug":"resumo-cpc-27-ativo-imobilizado-veja-os-principais-pontos-deste-pronunciamento","status":"publish","type":"post","link":"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-cpc-27-ativo-imobilizado-veja-os-principais-pontos-deste-pronunciamento\/","title":{"rendered":"Resumo CPC 27 \u2013 Ativo Imobilizado. Veja os principais pontos deste Pronunciamento."},"content":{"rendered":"\n<p class=\"has-medium-font-size\">J\u00e1 tem anotado o <strong>Resumo do CPC Ativo Imobilizado<\/strong>? N\u00e3o saia deste artigo sem saber os principais pontos deste Pronunciamento Cont\u00e1bil<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-medium\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"155\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/06\/15124711\/a_5747_09ca71e111acf2bf4fea38b7c1d54ca0-300x155.jpg\" alt=\"resumo cpc 27\" class=\"wp-image-526758\" srcset=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/06\/15124711\/a_5747_09ca71e111acf2bf4fea38b7c1d54ca0-300x155.jpg 300w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/06\/15124711\/a_5747_09ca71e111acf2bf4fea38b7c1d54ca0.jpg 600w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><figcaption>Resumo CPC 27 &#8211; Ativo Imobilizado<\/figcaption><\/figure><\/div>\n\n\n\n<p>Ol\u00e1 Estrategista. Tudo joia?<\/p>\n\n\n\n<p>Neste artigo iremos dar prosseguimento ao projeto de <strong>resumos dos<\/strong> <strong>principais Pronunciamentos Cont\u00e1beis<\/strong> emitidos pelo Comit\u00ea de Pronunciamentos Cont\u00e1beis (CPC).<\/p>\n\n\n\n<p>No <em>post<\/em> anterior apresentamos o resumo do CPC 25: Provis\u00f5es, Passivos e Ativos Contingentes. <a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/?p=522080\">Confira aqui<\/a>.<\/p>\n\n\n\n<p>Reiteramos que n\u00e3o vale a pena ler todos os CPCs, haja vista a extens\u00e3o de cada um deles e a quantidade de conte\u00fado irrelevante para concursos p\u00fablicos. Portanto, esta s\u00e9rie de artigos ir\u00e1 apresentar apenas os t\u00f3picos dos Pronunciamentos que podem vir a ser cobrados nos certames.<\/p>\n\n\n\n<p>Al\u00e9m disso, iremos abordar os t\u00f3picos em sua literalidade, uma vez que muitas quest\u00f5es s\u00e3o apresentadas dessa forma aos candidatos. Gostaria ainda de <strong>explica\u00e7\u00f5es mais detalhadas<\/strong>, com <strong>exemplos pr\u00e1ticos<\/strong> e resolu\u00e7\u00e3o <strong>passo a passo<\/strong> dos exerc\u00edcios?! <a href=\"https:\/\/www.estrategiaconcursos.com.br\/cursosPorMateria\/contabilidade-avancada-201\/\">Acesse aqui<\/a> nossos cursos de Contabilidade para Concursos, elaborados pelos melhores professores da \u00e1rea.<\/p>\n\n\n\n<p>Vamos ent\u00e3o ao Resumo <a href=\"http:\/\/static.cpc.aatb.com.br\/Documentos\/316_CPC_27_rev%2014.pdf\">CPC 27 Imobilizado<\/a>.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Resumo CPC 27 \u2013 Ativo Imobilizado<\/h2>\n\n\n\n<p>Antes de mais nada, Este Pronunciamento <strong>n\u00e3o<\/strong> se aplica a:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>ativos imobilizados classificados como mantidos para venda;<\/li><li>ativos biol\u00f3gicos relacionados com a atividade agr\u00edcola que n\u00e3o sejam plantas portadoras. Este pronunciamento aplica-se \u00e0s plantas portadoras, mas n\u00e3o se aplica aos produtos dessas plantas portadoras;<\/li><li>reconhecimento e mensura\u00e7\u00e3o de ativos de explora\u00e7\u00e3o e avalia\u00e7\u00e3o;<\/li><li>direitos sobre jazidas e reservas minerais tais como petr\u00f3leo, g\u00e1s natural, carv\u00e3o mineral, dolomita e recursos n\u00e3o renov\u00e1veis semelhantes.<\/li><\/ul>\n\n\n\n<p>Contudo, este Pronunciamento aplica-se aos ativos imobilizados usados para desenvolver ou manter os ativos descritos nas al\u00edneas (b) a (d).<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Defini\u00e7\u00f5es<\/h2>\n\n\n\n<p><strong>Valor cont\u00e1bil<\/strong> \u00e9 o valor pelo qual um ativo \u00e9 reconhecido ap\u00f3s a dedu\u00e7\u00e3o da deprecia\u00e7\u00e3o e da perda por redu\u00e7\u00e3o ao valor recuper\u00e1vel acumuladas.<\/p>\n\n\n\n<p>Planta portadora \u00e9 uma planta viva que:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>\u00e9 utilizada na produ\u00e7\u00e3o ou no fornecimento de produtos agr\u00edcolas;<\/li><li>\u00e9 cultivada para produzir frutos por mais de um per\u00edodo; e<\/li><li>tem uma probabilidade remota de ser vendida como produto agr\u00edcola, exceto para eventual venda como sucata.<\/li><\/ul>\n\n\n\n<p><strong>Ativo imobilizado<\/strong> \u00e9 o item tang\u00edvel que:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>\u00e9 mantido para uso na produ\u00e7\u00e3o ou fornecimento de mercadorias ou servi\u00e7os, para aluguel a outros, ou para fins administrativos; e<\/li><li>se espera utilizar por mais de um per\u00edodo.<\/li><\/ul>\n\n\n\n<p>Correspondem aos direitos que tenham por objeto bens corp\u00f3reos destinados \u00e0 manuten\u00e7\u00e3o das atividades da entidade ou exercidos com essa finalidade, inclusive os decorrentes de opera\u00e7\u00f5es que transfiram a ela os benef\u00edcios, os riscos e o controle desses bens.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Reconhecimento<\/h2>\n\n\n\n<p>O custo de um item de ativo imobilizado deve ser reconhecido como ativo se, e apenas se:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>for prov\u00e1vel que futuros benef\u00edcios econ\u00f4micos associados ao item fluir\u00e3o para a entidade; e<\/li><li>o custo do item puder ser mensurado confiavelmente.<\/li><\/ul>\n\n\n\n<p>Sobressalentes, pe\u00e7as de reposi\u00e7\u00e3o, ferramentas e equipamentos de uso interno s\u00e3o classificados como ativo imobilizado quando a entidade <strong>espera us\u00e1-los por mais de um per\u00edodo<\/strong>. Da mesma forma, se puderem ser utilizados somente em conex\u00e3o com itens do ativo imobilizado, tamb\u00e9m s\u00e3o contabilizados como ativo imobilizado.<\/p>\n\n\n\n<p>Partes de alguns itens do ativo imobilizado podem requerer substitui\u00e7\u00e3o em intervalos regulares. Por exemplo, um forno pode requerer novo revestimento ap\u00f3s um n\u00famero espec\u00edfico de horas de uso; ou o interior dos avi\u00f5es, como bancos e equipamentos internos, pode exigir substitui\u00e7\u00e3o diversas vezes durante a vida da estrutura.<\/p>\n\n\n\n<p>Itens do ativo imobilizado tamb\u00e9m podem ser adquiridos para efetuar substitui\u00e7\u00e3o recorrente menos frequente, tal como a substitui\u00e7\u00e3o das paredes interiores de edif\u00edcio, ou para efetuar substitui\u00e7\u00e3o n\u00e3o recorrente.<\/p>\n\n\n\n<p>Segundo o resumo CPC 27, a entidade reconhece no valor cont\u00e1bil de um item do ativo imobilizado o custo da pe\u00e7a reposta desse item quando o custo \u00e9 incorrido se os crit\u00e9rios de reconhecimento forem atendidos. O valor cont\u00e1bil das pe\u00e7as que s\u00e3o substitu\u00eddas \u00e9 baixado de acordo com as disposi\u00e7\u00f5es de baixa deste Pronunciamento.<\/p>\n\n\n\n<p>Uma condi\u00e7\u00e3o para continuar a operar um item do ativo imobilizado (por exemplo, uma aeronave) pode ser a realiza\u00e7\u00e3o regular de inspe\u00e7\u00f5es importantes em busca de falhas, independentemente das pe\u00e7as desse item serem ou n\u00e3o substitu\u00eddas.<\/p>\n\n\n\n<p>Quando cada inspe\u00e7\u00e3o importante for efetuada, o seu custo \u00e9 reconhecido no valor cont\u00e1bil do item do ativo imobilizado como uma substitui\u00e7\u00e3o se os crit\u00e9rios de reconhecimento forem satisfeitos. Qualquer valor cont\u00e1bil remanescente do custo da inspe\u00e7\u00e3o anterior (distinta das pe\u00e7as f\u00edsicas) \u00e9 baixado.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Mensura\u00e7\u00e3o<\/h2>\n\n\n\n<p>Um item do ativo imobilizado que seja classificado para reconhecimento como ativo deve ser mensurado pelo seu custo.<\/p>\n\n\n\n<p>O custo de um item do ativo imobilizado compreende:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>seu pre\u00e7o de aquisi\u00e7\u00e3o, acrescido de impostos de importa\u00e7\u00e3o e impostos n\u00e3o recuper\u00e1veis sobre a compra, depois de deduzidos os descontos comerciais e abatimentos;<\/li><li>quaisquer custos diretamente atribu\u00edveis para colocar o ativo no local e condi\u00e7\u00e3o necess\u00e1rias para o mesmo ser capaz de funcionar da forma pretendida pela administra\u00e7\u00e3o;<\/li><li>a estimativa inicial dos custos de desmontagem e remo\u00e7\u00e3o do item e de restaura\u00e7\u00e3o do local (s\u00edtio) no qual este est\u00e1 localizado.<\/li><\/ul>\n\n\n\n<p>Exemplos de custos diretamente atribu\u00edveis s\u00e3o:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>custos de benef\u00edcios aos empregados decorrentes diretamente da constru\u00e7\u00e3o ou aquisi\u00e7\u00e3o de item do ativo imobilizado;<\/li><li>o custo de prepara\u00e7\u00e3o do local;<\/li><li>os custos de frete e de manuseio (para recebimento e instala\u00e7\u00e3o);<\/li><li>o custo de instala\u00e7\u00e3o e montagem;<\/li><li>custos com testes para verificar se o ativo est\u00e1 funcionando corretamente, ap\u00f3s dedu\u00e7\u00e3o das receitas l\u00edquidas provenientes da venda de qualquer item produzido enquanto se coloca o ativo nesse local e condi\u00e7\u00e3o (tais como amostras produzidas quando se testa o equipamento); e<\/li><li>honor\u00e1rios profissionais.<\/li><\/ul>\n\n\n\n<p>Exemplos que <strong>n\u00e3o<\/strong> s\u00e3o custos de um item do ativo imobilizado s\u00e3o:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>custos de abertura de nova instala\u00e7\u00e3o;<\/li><li>os custos incorridos na introdu\u00e7\u00e3o de novo produto ou servi\u00e7o (incluindo propaganda e atividades promocionais);<\/li><li>custos da transfer\u00eancia das atividades para novo local ou para nova categoria de clientes (incluindo custos de treinamento); e<\/li><li>custos administrativos e outros custos indiretos.<\/li><\/ul>\n\n\n\n<h3 class=\"wp-block-heading\">Fim do Reconhecimento dos Custos<\/h3>\n\n\n\n<p>O reconhecimento dos custos no valor cont\u00e1bil de um item do ativo imobilizado cessa quando o item est\u00e1 no local e nas condi\u00e7\u00f5es operacionais pretendidas pela administra\u00e7\u00e3o.<\/p>\n\n\n\n<p>Portanto, os custos incorridos no uso ou na transfer\u00eancia ou reinstala\u00e7\u00e3o de um item n\u00e3o s\u00e3o inclu\u00eddos no seu valor cont\u00e1bil, como, por exemplo, os seguintes custos:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>custos incorridos durante o per\u00edodo em que o ativo capaz de operar nas condi\u00e7\u00f5es operacionais pretendidas pela administra\u00e7\u00e3o n\u00e3o \u00e9 utilizado ou est\u00e1 sendo operado a uma capacidade inferior \u00e0 sua capacidade total;<\/li><li>preju\u00edzos operacionais iniciais, tais como os incorridos enquanto a demanda pelos produtos do ativo \u00e9 estabelecida; e<\/li><li>custos de realoca\u00e7\u00e3o ou reorganiza\u00e7\u00e3o de parte ou de todas as opera\u00e7\u00f5es da entidade.<\/li><\/ul>\n\n\n\n<p>Ainda, segundo o Resumo CPC 27, algumas opera\u00e7\u00f5es realizadas em conex\u00e3o com a constru\u00e7\u00e3o ou o desenvolvimento de um item do ativo imobilizado n\u00e3o s\u00e3o necess\u00e1rias para deix\u00e1-lo no local e nas condi\u00e7\u00f5es operacionais pretendidas pela administra\u00e7\u00e3o.<\/p>\n\n\n\n<p>Destarte, essas atividades eventuais podem ocorrer antes ou durante as atividades de constru\u00e7\u00e3o ou desenvolvimento. Por exemplo, o local de constru\u00e7\u00e3o pode ser usado como estacionamento e gerar receitas, at\u00e9 que a constru\u00e7\u00e3o se inicie.<\/p>\n\n\n\n<p>Como essas atividades n\u00e3o s\u00e3o necess\u00e1rias para que o ativo fique em condi\u00e7\u00f5es de funcionar no local e nas condi\u00e7\u00f5es operacionais pretendidas pela administra\u00e7\u00e3o, as receitas e as despesas relacionadas devem ser reconhecidas no resultado e inclu\u00eddas nas respectivas classifica\u00e7\u00f5es de receita e despesa.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Mensura\u00e7\u00e3o do Custo<\/h2>\n\n\n\n<p>O custo de um item de ativo imobilizado \u00e9 equivalente ao pre\u00e7o \u00e0 vista na data do reconhecimento. Se o prazo de pagamento excede os prazos normais de cr\u00e9dito, a diferen\u00e7a entre o pre\u00e7o equivalente \u00e0 vista e o total dos pagamentos deve ser reconhecida como despesa com juros durante o per\u00edodo, a menos que seja pass\u00edvel de capitaliza\u00e7\u00e3o.<\/p>\n\n\n\n<p>Um ativo imobilizado pode ser adquirido por meio de permuta por ativo n\u00e3o monet\u00e1rio. Nesse caso, o custo de tal item do ativo imobilizado \u00e9 mensurado pelo <strong>valor justo<\/strong> a n\u00e3o ser que:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>a opera\u00e7\u00e3o de permuta n\u00e3o tenha natureza comercial ou;<\/li><li>o valor justo do ativo recebido e do ativo cedido n\u00e3o possam ser mensurados com seguran\u00e7a.<\/li><\/ul>\n\n\n\n<p>O valor justo de um ativo \u00e9 mensur\u00e1vel de forma confi\u00e1vel:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>se a variabilidade da faixa de mensura\u00e7\u00e3o de valor justo razo\u00e1vel n\u00e3o for significativa ou;<\/li><li>se as probabilidades de v\u00e1rias estimativas, dentro dessa faixa, puderem ser razoavelmente avaliadas e utilizadas na mensura\u00e7\u00e3o do valor justo.<\/li><\/ul>\n\n\n\n<p><strong>Ap\u00f3s o reconhecimento como ativo, um item do ativo imobilizado deve ser apresentado ao custo menos qualquer deprecia\u00e7\u00e3o e perda por redu\u00e7\u00e3o ao valor recuper\u00e1vel acumuladas.<\/strong><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Reavalia\u00e7\u00e3o<\/h2>\n\n\n\n<p>Ap\u00f3s o reconhecimento como um ativo, o item do ativo imobilizado cujo valor justo possa ser mensurado confiavelmente pode ser apresentado, <strong>se permitido por lei, pelo seu valor reavaliado<\/strong>, correspondente ao seu valor justo \u00e0 data da reavalia\u00e7\u00e3o menos qualquer deprecia\u00e7\u00e3o e perda por redu\u00e7\u00e3o ao valor recuper\u00e1vel acumuladas subsequentes.<\/p>\n\n\n\n<p>Se o m\u00e9todo de reavalia\u00e7\u00e3o for permitido por lei e um item do ativo imobilizado for reavaliado, toda a classe do ativo imobilizado \u00e0 qual pertence esse ativo deve ser reavaliado.<\/p>\n\n\n\n<p><strong>Se o valor cont\u00e1bil do ativo aumentar em virtude de reavalia\u00e7\u00e3o, esse aumento deve ser creditado diretamente \u00e0 conta pr\u00f3pria do PATRIM\u00d4NIO L\u00cdQUIDO. No entanto, o aumento deve ser reconhecido no RESULTADO quando se tratar da revers\u00e3o de decr\u00e9scimo de reavalia\u00e7\u00e3o do mesmo ativo anteriormente reconhecido no resultado.<\/strong><\/p>\n\n\n\n<p><strong>Se o valor cont\u00e1bil do ativo diminuir em virtude de reavalia\u00e7\u00e3o, essa diminui\u00e7\u00e3o deve ser reconhecida no RESULTADO. No entanto, se houver saldo de reserva de reavalia\u00e7\u00e3o, a diminui\u00e7\u00e3o do ativo deve ser debitada diretamente ao patrim\u00f4nio l\u00edquido contra a conta de reserva de reavalia\u00e7\u00e3o, at\u00e9 o seu limite.<\/strong><\/p>\n\n\n\n<p>O saldo relativo \u00e0 reavalia\u00e7\u00e3o acumulada do item do ativo imobilizado inclu\u00eddo no patrim\u00f4nio l\u00edquido somente pode ser transferido para lucros acumulados quando a reserva \u00e9 realizada.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Deprecia\u00e7\u00e3o<\/h2>\n\n\n\n<p>O valor depreci\u00e1vel de um ativo deve ser apropriado de forma sistem\u00e1tica ao longo da sua vida \u00fatil estimada.<\/p>\n\n\n\n<p>O valor residual e a vida \u00fatil de um ativo s\u00e3o revisados pelo menos ao final de cada exerc\u00edcio e, se as expectativas diferirem das estimativas anteriores, a mudan\u00e7a deve ser contabilizada como mudan\u00e7a de estimativa cont\u00e1bil.<\/p>\n\n\n\n<p>A deprecia\u00e7\u00e3o \u00e9 reconhecida mesmo que o valor justo do ativo exceda o seu valor cont\u00e1bil, desde que o valor residual do ativo n\u00e3o exceda o seu valor cont\u00e1bil. <strong>A repara\u00e7\u00e3o e a manuten\u00e7\u00e3o de um ativo n\u00e3o evitam a necessidade de depreci\u00e1-lo.<\/strong><\/p>\n\n\n\n<p>Ainda, segundo Resumo CPC 27, a deprecia\u00e7\u00e3o do ativo se inicia quando este est\u00e1 dispon\u00edvel para uso, ou seja, quando est\u00e1 no local e em condi\u00e7\u00e3o de funcionamento na forma pretendida pela administra\u00e7\u00e3o.<\/p>\n\n\n\n<p>O valor residual de um ativo pode aumentar. A despesa de deprecia\u00e7\u00e3o ser\u00e1 zero enquanto o valor residual subsequente for igual ou superior ao seu valor cont\u00e1bil.<\/p>\n\n\n\n<p>Cada componente de um item do ativo imobilizado com custo significativo em rela\u00e7\u00e3o ao custo total do item deve ser depreciado separadamente.<\/p>\n\n\n\n<p>Um componente significativo de um item do ativo imobilizado pode ter a vida \u00fatil e o m\u00e9todo de deprecia\u00e7\u00e3o que sejam os mesmos que a vida \u00fatil e o m\u00e9todo de deprecia\u00e7\u00e3o de outro componente significativo do mesmo item. Esses componentes podem ser agrupados no c\u00e1lculo da despesa de deprecia\u00e7\u00e3o.<\/p>\n\n\n\n<p>A despesa de deprecia\u00e7\u00e3o de cada per\u00edodo deve ser reconhecida no resultado <strong>a menos que seja inclu\u00edda no valor cont\u00e1bil de outro ativo<\/strong>. Por exemplo, a deprecia\u00e7\u00e3o de m\u00e1quinas e equipamentos de produ\u00e7\u00e3o \u00e9 inclu\u00edda nos custos de produ\u00e7\u00e3o de estoque.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">M\u00e9todo de Deprecia\u00e7\u00e3o<\/h2>\n\n\n\n<p>O m\u00e9todo de deprecia\u00e7\u00e3o aplicado a um ativo deve ser revisado pelo menos ao final de cada exerc\u00edcio e, se houver altera\u00e7\u00e3o significativa no padr\u00e3o de consumo previsto, o m\u00e9todo de deprecia\u00e7\u00e3o deve ser alterado para refletir essa mudan\u00e7a.<\/p>\n\n\n\n<p>O m\u00e9todo de deprecia\u00e7\u00e3o que se baseia na receita que \u00e9 gerada pela atividade que inclui a utiliza\u00e7\u00e3o de ativo <strong>n\u00e3o \u00e9 apropriado<\/strong>.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Baixa<\/h2>\n\n\n\n<p>O valor cont\u00e1bil de um item do ativo imobilizado deve ser baixado:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>por ocasi\u00e3o de sua aliena\u00e7\u00e3o; ou<\/li><li>quando n\u00e3o h\u00e1 expectativa de benef\u00edcios econ\u00f4micos futuros com a sua utiliza\u00e7\u00e3o ou aliena\u00e7\u00e3o.<\/li><\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">Finalizando<\/h2>\n\n\n\n<p>E a\u00ed, curtiu esse artigo sobre o resumo CPC 27?! Deixe seu coment\u00e1rio.<\/p>\n\n\n\n<p>Gostaria ainda de <strong>explica\u00e7\u00f5es mais detalhadas<\/strong>, com <strong>exemplos pr\u00e1ticos<\/strong> e resolu\u00e7\u00e3o <strong>passo a passo<\/strong> dos exerc\u00edcios?! <a href=\"https:\/\/www.estrategiaconcursos.com.br\/cursosPorMateria\/contabilidade-avancada-201\/\">Acesse aqui<\/a> nossos cursos de Contabilidade para Concursos, elaborados pelos melhores professores da \u00e1rea.<\/p>\n\n\n\n<p>Forte abra\u00e7o<\/p>\n\n\n\n<p><strong>Instagram: <\/strong><a href=\"https:\/\/www.instagram.com\/leandro.rms12\/\">https:\/\/www.instagram.com\/leandro.rms12\/<\/a> <\/p>\n\n\n\n<p style=\"font-size:18px\" class=\"has-text-color has-background has-text-align-center has-very-light-gray-color has-vivid-purple-background-color\"><strong>SISTEMA DE QUEST\u00d5ES &#8211; <a href=\"https:\/\/questoes.estrategiaconcursos.com.br\/\">Experimente Gr\u00e1tis por 7 dias<\/a><\/strong><\/p>\n\n\n\n<p class=\"has-text-align-center has-medium-font-size\"><em><strong>Assinatura Anual Ilimitada*<\/strong><\/em><\/p>\n\n\n\n<p class=\"has-text-align-center\"><em>Prepare-se com o melhor material e com quem mais aprova em Concursos P\u00fablicos em todo o pa\u00eds. Assine agora a nossa Assinatura Anual e tenha acesso ilimitado* a todos os nossos cursos.<\/em><\/p>\n\n\n\n<p style=\"font-size:22px\" class=\"has-background has-text-align-center has-luminous-vivid-amber-background-color\"><strong>ASSINE AGORA<\/strong>&nbsp;\u2013&nbsp;<a rel=\"noreferrer noopener\" href=\"https:\/\/www.estrategiaconcursos.com.br\/assinaturas\" target=\"_blank\"><strong>Assinatura Ilimitada<\/strong><\/a><\/p>\n\n\n\n<p class=\"has-text-align-center has-medium-font-size\"><em><strong>Fique por dentro de todos os concursos<\/strong><\/em>:<\/p>\n\n\n\n<p style=\"font-size:22px\" class=\"has-background has-text-align-center has-pale-cyan-blue-background-color\"><a rel=\"noreferrer noopener\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-abertos\/\" target=\"_blank\"><strong>Concursos abertos<\/strong><\/a><\/p>\n\n\n\n<p style=\"font-size:22px\" class=\"has-background has-text-align-center has-pale-cyan-blue-background-color\"><a rel=\"noreferrer noopener\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-2020\/\" target=\"_blank\"><strong>Concursos 2020<\/strong><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>J\u00e1 tem anotado o Resumo do CPC Ativo Imobilizado? N\u00e3o saia deste artigo sem saber os principais pontos deste Pronunciamento Cont\u00e1bil Ol\u00e1 Estrategista. Tudo joia? Neste artigo iremos dar prosseguimento ao projeto de resumos dos principais Pronunciamentos Cont\u00e1beis emitidos pelo Comit\u00ea de Pronunciamentos Cont\u00e1beis (CPC). No post anterior apresentamos o resumo do CPC 25: Provis\u00f5es, [&hellip;]<\/p>\n","protected":false},"author":1668,"featured_media":526758,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"post_tipo":"article","footnotes":""},"categories":[1,1983],"tags":[196704,196705,196703],"tax_estado":[],"class_list":["post-526754","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cursos-e-concursos","category-fiscal-estadual","tag-ativo-imobilizado","tag-cpc-27","tag-imobilizado"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.2 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Resumo CPC 27 \u2013 Ativo Imobilizado. P pontos do Pronunciamento.<\/title>\n<meta name=\"description\" content=\"Resumo CPC 27. Saiba os principais pontos desde Pronunciamento Cont\u00e1bil, e os itens mais cobrados nas provas de concurso.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-cpc-27-ativo-imobilizado-veja-os-principais-pontos-deste-pronunciamento\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Resumo CPC 27 \u2013 Ativo Imobilizado. Veja os principais pontos deste Pronunciamento.\" \/>\n<meta property=\"og:description\" content=\"Resumo CPC 27. Saiba os principais pontos desde Pronunciamento Cont\u00e1bil, e os itens mais cobrados nas provas de concurso.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-cpc-27-ativo-imobilizado-veja-os-principais-pontos-deste-pronunciamento\/\" \/>\n<meta property=\"og:site_name\" content=\"Estrat\u00e9gia Concursos\" \/>\n<meta property=\"article:published_time\" content=\"2020-07-01T19:10:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/06\/15124711\/a_5747_09ca71e111acf2bf4fea38b7c1d54ca0.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"310\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Leandro Ricardo Machado da Silveira\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:site\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Leandro Ricardo Machado da Silveira\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"12 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-cpc-27-ativo-imobilizado-veja-os-principais-pontos-deste-pronunciamento\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-cpc-27-ativo-imobilizado-veja-os-principais-pontos-deste-pronunciamento\/\"},\"author\":{\"name\":\"Leandro Ricardo Machado da Silveira\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/c666a44fbce7e2e70009a9c13549267a\"},\"headline\":\"Resumo CPC 27 \u2013 Ativo Imobilizado. Veja os principais pontos deste Pronunciamento.\",\"datePublished\":\"2020-07-01T19:10:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-cpc-27-ativo-imobilizado-veja-os-principais-pontos-deste-pronunciamento\/\"},\"wordCount\":2344,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-cpc-27-ativo-imobilizado-veja-os-principais-pontos-deste-pronunciamento\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/06\/15124711\/a_5747_09ca71e111acf2bf4fea38b7c1d54ca0.jpg\",\"keywords\":[\"ativo imobilizado\",\"cpc 27\",\"imobilizado\"],\"articleSection\":[\"Concursos P\u00fablicos\",\"Fiscal - Estadual (ICMS)\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-cpc-27-ativo-imobilizado-veja-os-principais-pontos-deste-pronunciamento\/#respond\"]}],\"copyrightYear\":\"2020\",\"copyrightHolder\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-cpc-27-ativo-imobilizado-veja-os-principais-pontos-deste-pronunciamento\/\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-cpc-27-ativo-imobilizado-veja-os-principais-pontos-deste-pronunciamento\/\",\"name\":\"Resumo CPC 27 \u2013 Ativo Imobilizado. P pontos do Pronunciamento.\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-cpc-27-ativo-imobilizado-veja-os-principais-pontos-deste-pronunciamento\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-cpc-27-ativo-imobilizado-veja-os-principais-pontos-deste-pronunciamento\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/06\/15124711\/a_5747_09ca71e111acf2bf4fea38b7c1d54ca0.jpg\",\"datePublished\":\"2020-07-01T19:10:00+00:00\",\"description\":\"Resumo CPC 27. Saiba os principais pontos desde Pronunciamento Cont\u00e1bil, e os itens mais cobrados nas provas de concurso.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-cpc-27-ativo-imobilizado-veja-os-principais-pontos-deste-pronunciamento\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-cpc-27-ativo-imobilizado-veja-os-principais-pontos-deste-pronunciamento\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-cpc-27-ativo-imobilizado-veja-os-principais-pontos-deste-pronunciamento\/#primaryimage\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/06\/15124711\/a_5747_09ca71e111acf2bf4fea38b7c1d54ca0.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/06\/15124711\/a_5747_09ca71e111acf2bf4fea38b7c1d54ca0.jpg\",\"width\":600,\"height\":310},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-cpc-27-ativo-imobilizado-veja-os-principais-pontos-deste-pronunciamento\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Resumo CPC 27 \u2013 Ativo Imobilizado. Veja os principais pontos deste Pronunciamento.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"name\":\"Estrat\u00e9gia Concursos\",\"description\":\"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.\",\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\",\"name\":\"Estrat\u00e9gia Concursos\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"width\":230,\"height\":60,\"caption\":\"Estrat\u00e9gia Concursos\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/EstratConcursos\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/c666a44fbce7e2e70009a9c13549267a\",\"name\":\"Leandro Ricardo Machado da Silveira\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/6fb25994d16b9649838400aa459b16c1c83f558e0fd6ebebd16da0473908b291?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/6fb25994d16b9649838400aa459b16c1c83f558e0fd6ebebd16da0473908b291?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/6fb25994d16b9649838400aa459b16c1c83f558e0fd6ebebd16da0473908b291?s=96&d=mm&r=g\",\"caption\":\"Leandro Ricardo Machado da Silveira\"},\"description\":\"Engenheiro Aeron\u00e1utico, formado pela Universidade Federal de Uberl\u00e2ndia, possui MBA em Administra\u00e7\u00e3o e Finan\u00e7as Corporativas e aprovado nos concursos de Auditor Fiscal SEFAZ-SC e SEFAZ-GO.\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/leandro_vzthotmail-com\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Resumo CPC 27 \u2013 Ativo Imobilizado. P pontos do Pronunciamento.","description":"Resumo CPC 27. Saiba os principais pontos desde Pronunciamento Cont\u00e1bil, e os itens mais cobrados nas provas de concurso.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-cpc-27-ativo-imobilizado-veja-os-principais-pontos-deste-pronunciamento\/","og_locale":"pt_BR","og_type":"article","og_title":"Resumo CPC 27 \u2013 Ativo Imobilizado. Veja os principais pontos deste Pronunciamento.","og_description":"Resumo CPC 27. Saiba os principais pontos desde Pronunciamento Cont\u00e1bil, e os itens mais cobrados nas provas de concurso.","og_url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-cpc-27-ativo-imobilizado-veja-os-principais-pontos-deste-pronunciamento\/","og_site_name":"Estrat\u00e9gia Concursos","article_published_time":"2020-07-01T19:10:00+00:00","og_image":[{"width":600,"height":310,"url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/06\/15124711\/a_5747_09ca71e111acf2bf4fea38b7c1d54ca0.jpg","type":"image\/jpeg"}],"author":"Leandro Ricardo Machado da Silveira","twitter_card":"summary_large_image","twitter_creator":"@EstratConcursos","twitter_site":"@EstratConcursos","twitter_misc":{"Escrito por":"Leandro Ricardo Machado da Silveira","Est. tempo de leitura":"12 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-cpc-27-ativo-imobilizado-veja-os-principais-pontos-deste-pronunciamento\/#article","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-cpc-27-ativo-imobilizado-veja-os-principais-pontos-deste-pronunciamento\/"},"author":{"name":"Leandro Ricardo Machado da Silveira","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/c666a44fbce7e2e70009a9c13549267a"},"headline":"Resumo CPC 27 \u2013 Ativo Imobilizado. Veja os principais pontos deste Pronunciamento.","datePublished":"2020-07-01T19:10:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-cpc-27-ativo-imobilizado-veja-os-principais-pontos-deste-pronunciamento\/"},"wordCount":2344,"commentCount":0,"publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-cpc-27-ativo-imobilizado-veja-os-principais-pontos-deste-pronunciamento\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/06\/15124711\/a_5747_09ca71e111acf2bf4fea38b7c1d54ca0.jpg","keywords":["ativo imobilizado","cpc 27","imobilizado"],"articleSection":["Concursos P\u00fablicos","Fiscal - Estadual (ICMS)"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-cpc-27-ativo-imobilizado-veja-os-principais-pontos-deste-pronunciamento\/#respond"]}],"copyrightYear":"2020","copyrightHolder":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-cpc-27-ativo-imobilizado-veja-os-principais-pontos-deste-pronunciamento\/","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-cpc-27-ativo-imobilizado-veja-os-principais-pontos-deste-pronunciamento\/","name":"Resumo CPC 27 \u2013 Ativo Imobilizado. P pontos do Pronunciamento.","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-cpc-27-ativo-imobilizado-veja-os-principais-pontos-deste-pronunciamento\/#primaryimage"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-cpc-27-ativo-imobilizado-veja-os-principais-pontos-deste-pronunciamento\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/06\/15124711\/a_5747_09ca71e111acf2bf4fea38b7c1d54ca0.jpg","datePublished":"2020-07-01T19:10:00+00:00","description":"Resumo CPC 27. Saiba os principais pontos desde Pronunciamento Cont\u00e1bil, e os itens mais cobrados nas provas de concurso.","breadcrumb":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-cpc-27-ativo-imobilizado-veja-os-principais-pontos-deste-pronunciamento\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-cpc-27-ativo-imobilizado-veja-os-principais-pontos-deste-pronunciamento\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-cpc-27-ativo-imobilizado-veja-os-principais-pontos-deste-pronunciamento\/#primaryimage","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/06\/15124711\/a_5747_09ca71e111acf2bf4fea38b7c1d54ca0.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/06\/15124711\/a_5747_09ca71e111acf2bf4fea38b7c1d54ca0.jpg","width":600,"height":310},{"@type":"BreadcrumbList","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-cpc-27-ativo-imobilizado-veja-os-principais-pontos-deste-pronunciamento\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.estrategiaconcursos.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Resumo CPC 27 \u2013 Ativo Imobilizado. Veja os principais pontos deste Pronunciamento."}]},{"@type":"WebSite","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","name":"Estrat\u00e9gia Concursos","description":"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.","publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization","name":"Estrat\u00e9gia Concursos","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","width":230,"height":60,"caption":"Estrat\u00e9gia Concursos"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/EstratConcursos"]},{"@type":"Person","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/c666a44fbce7e2e70009a9c13549267a","name":"Leandro Ricardo Machado da Silveira","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/6fb25994d16b9649838400aa459b16c1c83f558e0fd6ebebd16da0473908b291?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/6fb25994d16b9649838400aa459b16c1c83f558e0fd6ebebd16da0473908b291?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6fb25994d16b9649838400aa459b16c1c83f558e0fd6ebebd16da0473908b291?s=96&d=mm&r=g","caption":"Leandro Ricardo Machado da Silveira"},"description":"Engenheiro Aeron\u00e1utico, formado pela Universidade Federal de Uberl\u00e2ndia, possui MBA em Administra\u00e7\u00e3o e Finan\u00e7as Corporativas e aprovado nos concursos de Auditor Fiscal SEFAZ-SC e SEFAZ-GO.","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/leandro_vzthotmail-com\/"}]}},"_links":{"self":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/526754","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/users\/1668"}],"replies":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/comments?post=526754"}],"version-history":[{"count":2,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/526754\/revisions"}],"predecessor-version":[{"id":526764,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/526754\/revisions\/526764"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media\/526758"}],"wp:attachment":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media?parent=526754"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/categories?post=526754"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tags?post=526754"},{"taxonomy":"tax_estado","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tax_estado?post=526754"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}