{"id":526056,"date":"2020-07-09T18:33:00","date_gmt":"2020-07-09T21:33:00","guid":{"rendered":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?p=526056"},"modified":"2022-10-07T11:19:07","modified_gmt":"2022-10-07T14:19:07","slug":"regra-de-tres-simples-e-composta-conceito-e-aplicacao","status":"publish","type":"post","link":"https:\/\/www.estrategiaconcursos.com.br\/blog\/regra-de-tres-simples-e-composta-conceito-e-aplicacao\/","title":{"rendered":"Regra de tr\u00eas simples e composta &#8211; conceito e aplica\u00e7\u00e3o"},"content":{"rendered":"\n<p>O artigo de hoje \u00e9 dedicado aos estudantes que t\u00eam dificuldades com matem\u00e1tica, em especial, com a <strong>regra de tr\u00eas simples e composta<\/strong>.<\/p>\n\n\n\n<p>Abordaremos o tema de forma bem pr\u00e1tica para facilitar seu aprendizado e garantir os pontos t\u00e3o preciosos na hora da prova. Vamos l\u00e1?<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-o-que-e-uma-regra-de-tres\">O que \u00e9 uma regra de tr\u00eas?<\/h2>\n\n\n\n<p><strong>Regra de tr\u00eas<\/strong> \u00e9 um m\u00e9todo matem\u00e1tico que possibilita encontrar um valor at\u00e9 ent\u00e3o desconhecido, considerando a <strong>proporcionalidade<\/strong> entre as vari\u00e1veis j\u00e1 conhecidas. Essas vari\u00e1veis podem ser diversas, tais como \u00e1rea, tempo, dinheiro etc.<\/p>\n\n\n\n<p>Trata-se de um m\u00e9todo muito \u00fatil para aplica\u00e7\u00f5es no dia a dia e o mais importante para n\u00f3s: \u00e9 <strong>muito cobrado em prova<\/strong>, direta ou indiretamente.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-a-relacao-das-grandezas\">A rela\u00e7\u00e3o das grandezas<\/h2>\n\n\n\n<p>Uma an\u00e1lise sempre necess\u00e1ria <span class=\"has-inline-color has-luminous-vivid-amber-color\"><strong>antes<\/strong> <\/span>de \u201csair calculando\u201d a <strong>regra de tr\u00eas<\/strong> \u00e9 verificar se as vari\u00e1veis s\u00e3o <strong><span class=\"has-inline-color has-vivid-cyan-blue-color\">diretamente proporcionais<\/span><\/strong> ou se s\u00e3o <strong><span class=\"has-inline-color has-vivid-red-color\">inversamente proporcionais<\/span><\/strong>.<\/p>\n\n\n\n<p>Dizemos que as vari\u00e1veis s\u00e3o <strong><span class=\"has-inline-color has-vivid-cyan-blue-color\">diretamente proporcionais<\/span><\/strong> quando o <strong>aumento de uma vari\u00e1vel ocasiona o aumento da outra,<\/strong> ao passo que as vari\u00e1veis s\u00e3o <span class=\"has-inline-color has-vivid-red-color\"><strong>inversamente<\/strong> <strong>proporcionais<\/strong><\/span> quando o <strong>aumento de uma faz com que a outra diminua<\/strong>.<\/p>\n\n\n\n<p>Exemplificando:<\/p>\n\n\n\n<p>A <strong>velocidade m\u00e9dia<\/strong> e o <strong>tempo<\/strong> de chegada no destino s\u00e3o vari\u00e1veis <strong><span class=\"has-inline-color has-vivid-red-color\">inversamente proporcionais<\/span><\/strong>, afinal quanto maior a velocidade, mais r\u00e1pido se chega (menos tempo).<\/p>\n\n\n\n<p>J\u00e1 a <strong>dist\u00e2ncia<\/strong> e o <strong>tempo<\/strong> (considerando uma velocidade m\u00e9dia constante) s\u00e3o vari\u00e1veis <span class=\"has-inline-color has-vivid-cyan-blue-color\"><strong>diretamente<\/strong> <strong>proporcionais<\/strong><\/span>, uma vez que quanto mais longe for (mais distante), maior ser\u00e1 o tempo para se chegar ao destino.<\/p>\n\n\n\n<p>Tranquilo, n\u00e9?<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-regra-de-tres-simples\">Regra de tr\u00eas simples<\/h2>\n\n\n\n<p>Na<strong> regra de tr\u00eas<\/strong> <strong>simples <\/strong>temos duas vari\u00e1veis e conhecemos tr\u00eas valores e desejamos encontrar o quarto. Vamos exemplificar.<\/p>\n\n\n\n<p><strong>Suponha que se estime 10 salgadinhos por pessoa para realizar uma festa de anivers\u00e1rio. Quantos salgadinhos precisar\u00e3o ser adquiridos, caso se deseje convidar 20 pessoas?<\/strong><\/p>\n\n\n\n<p>Lembre-se que a primeira an\u00e1lise a ser realizada \u00e9 a da proporcionalidade. Nesse caso, trata-se de duas vari\u00e1veis <span class=\"has-inline-color has-vivid-cyan-blue-color\"><strong>diretamente<\/strong> <strong>proporcionais<\/strong><\/span>, uma vez que ao aumentar o n\u00famero de convidados, deve-se comprar mais salgadinhos.<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"459\" height=\"156\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/06\/12103305\/image-163.png\" alt=\"regra de tr\u00eas\" class=\"wp-image-526062\" srcset=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/06\/12103305\/image-163.png 459w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/06\/12103305\/image-163-300x102.png 300w\" sizes=\"auto, (max-width: 459px) 100vw, 459px\" \/><\/figure>\n\n\n\n<p>Assim,<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"133\" height=\"82\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/06\/12103337\/image-164.png\" alt=\"c\u00e1lculo\" class=\"wp-image-526064\"\/><\/figure>\n\n\n\n<p>Multiplicando em \u201cX\u201d, teremos que:<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"308\" height=\"112\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/06\/12112538\/image-167.png\" alt=\"c\u00e1lculo\" class=\"wp-image-526098\" srcset=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/06\/12112538\/image-167.png 308w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/06\/12112538\/image-167-300x109.png 300w\" sizes=\"auto, (max-width: 308px) 100vw, 308px\" \/><\/figure>\n\n\n\n<p>Agora vamos considerar outra situa\u00e7\u00e3o.<\/p>\n\n\n\n<p><strong>Para construir uma casa, um pedreiro leva 30 dias. Quantos dias ser\u00e3o necess\u00e1rios para construir a casa se 5 pedreiros trabalharem simultaneamente?<\/strong><\/p>\n\n\n\n<p>As vari\u00e1veis s\u00e3o <strong><span class=\"has-inline-color has-vivid-red-color\">in<\/span><\/strong><span class=\"has-inline-color has-vivid-red-color\"><strong>versamente<\/strong> <strong>proporcionais<\/strong><\/span>, afinal, quanto mais pedreiros trabalhando, menos dias ser\u00e3o necess\u00e1rios para concluir a obra.<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"372\" height=\"163\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/06\/12112706\/image-168.png\" alt=\"tabela de proporcionalidade\" class=\"wp-image-526100\" srcset=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/06\/12112706\/image-168.png 372w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/06\/12112706\/image-168-300x131.png 300w\" sizes=\"auto, (max-width: 372px) 100vw, 372px\" \/><\/figure>\n\n\n\n<p>A consequ\u00eancia disso \u00e9 que devemos \u201cinverter\u201d um dos lados da nossa igualdade, logo:<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"283\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/06\/12112739\/image-169.png\" alt=\"c\u00e1lculo\" class=\"wp-image-526102\"\/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-regra-de-tres-composta\">Regra de tr\u00eas composta<\/h2>\n\n\n\n<p>A regra de tr\u00eas composta \u00e9 muito parecida com o que fizemos at\u00e9 aqui, por\u00e9m, teremos tr\u00eas vari\u00e1veis (\u00e0s vezes at\u00e9 4 em alguns exerc\u00edcios) e 6 valores (ou 8, no caso de 4 vari\u00e1veis), sendo um deles desconhecido.<\/p>\n\n\n\n<p>Vamos pegar o exemplo anterior (da constru\u00e7\u00e3o da casa) e acrescer um elemento: as horas trabalhadas por dia.<\/p>\n\n\n\n<p><strong>Imagine que para construir uma casa, um pedreiro leve 30 dias trabalhando 15 horas di\u00e1rias. Quantos dias ser\u00e3o necess\u00e1rios para construir essa casa se 5 pedreiros trabalharem simultaneamente durante 10 horas di\u00e1rias?<\/strong><\/p>\n\n\n\n<p>O primeiro passo para esse tipo de exerc\u00edcio \u00e9 &#8220;determinar uma seta\u201d e analisar quais ser\u00e3o as consequ\u00eancias para as demais vari\u00e1veis.<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"593\" height=\"156\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/06\/12112838\/image-170.png\" alt=\"Regra de tr\u00eas \" class=\"wp-image-526103\" srcset=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/06\/12112838\/image-170.png 593w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/06\/12112838\/image-170-300x79.png 300w\" sizes=\"auto, (max-width: 593px) 100vw, 593px\" \/><\/figure>\n\n\n\n<p><strong>Analisando a proporcionalidade:<\/strong> Se a quantidade de pedreiros aumenta (seta para cima), a quantidade de dias para concluir a obra ser\u00e1 menor (seta para baixo), da mesma forma que a quantidade de horas poder\u00e1 ser menor (seta para baixo).<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"590\" height=\"169\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/06\/12112927\/image-171.png\" alt=\"tabela de proporcionalidade\" class=\"wp-image-526104\" srcset=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/06\/12112927\/image-171.png 590w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/06\/12112927\/image-171-300x86.png 300w\" sizes=\"auto, (max-width: 590px) 100vw, 590px\" \/><\/figure>\n\n\n\n<p>Em termos matem\u00e1ticos, temos que:<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"186\" height=\"83\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/06\/12112951\/image-172.png\" alt=\"c\u00e1lculo\" class=\"wp-image-526105\"\/><\/figure>\n\n\n\n<p>Percebeu? Houve a invers\u00e3o das duas fra\u00e7\u00f5es relacionadas aos dias e \u00e0s horas, afinal, elas s\u00e3o <strong><span class=\"has-inline-color has-vivid-red-color\">inversamente proporcionais<\/span><\/strong> \u00e0 quantidade de pedreiros.<\/p>\n\n\n\n<p>Ent\u00e3o,<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"189\" height=\"326\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/06\/12113025\/image-173.png\" alt=\"c\u00e1lculo\" class=\"wp-image-526106\" srcset=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/06\/12113025\/image-173.png 189w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/06\/12113025\/image-173-174x300.png 174w\" sizes=\"auto, (max-width: 189px) 100vw, 189px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-vendo-na-pratica\">Vendo na pr\u00e1tica<\/h2>\n\n\n\n<p>Caso ainda tenha restado alguma d\u00favida, nada melhor do que realizar algumas <a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/questoes-de-concurso\/\" target=\"_blank\" rel=\"noreferrer noopener\">quest\u00f5es de concurso<\/a> para sanar essas lacunas.<\/p>\n\n\n\n<p>Iniciaremos com dois exemplos de <strong>regra de tr\u00eas simples.<\/strong><\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-exemplos-de-regra-de-tres-simples\">Exemplos de <strong>regra de tr\u00eas simples<\/strong><\/h3>\n\n\n\n<p><strong>FCC &#8211; Auxiliar Legislativo\/2020<\/strong><\/p>\n\n\n\n<p><strong>Uma empresa de 60 funcion\u00e1rios deve entregar uma encomenda em 30 dias. Ap\u00f3s 15 dias, apenas 3\/10 da encomenda havia sido produzida. Considerando que o ritmo de produ\u00e7\u00e3o de cada funcion\u00e1rio \u00e9 igual e constante, o n\u00famero adicional de funcion\u00e1rios que a empresa deve contratar para entregar a encomenda no prazo \u00e9<\/strong><\/p>\n\n\n\n<p><strong>a) 100<\/strong><\/p>\n\n\n\n<p><strong>b) 20<\/strong><\/p>\n\n\n\n<p><strong>c) 40<\/strong><\/p>\n\n\n\n<p><strong>d) 60<\/strong><\/p>\n\n\n\n<p><strong>e) 80<\/strong><\/p>\n\n\n\n<p>Vamos iniciar com a tabela das vari\u00e1veis, considerando que o <em>\u201co ritmo de produ\u00e7\u00e3o de cada funcion\u00e1rio \u00e9 igual e constante\u201d <\/em>e que o prazo para finalizar a encomenda \u00e9 de 15 dias (30 dias totais, menos 15 dias que j\u00e1 foram gastos para produzir 3\/10).<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"590\" height=\"124\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/06\/12113116\/image-174.png\" alt=\"Regra de tr\u00eas \" class=\"wp-image-526107\" srcset=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/06\/12113116\/image-174.png 590w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/06\/12113116\/image-174-300x63.png 300w\" sizes=\"auto, (max-width: 590px) 100vw, 590px\" \/><\/figure>\n\n\n\n<p>A vari\u00e1vel \u201cDias\u201d \u00e9 a mesma, ent\u00e3o, podemos desconsider\u00e1-la, pois seria uma fra\u00e7\u00e3o 15\/15, logo:<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"448\" height=\"121\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/06\/12113144\/image-175.png\" alt=\"Regra de tr\u00eas \" class=\"wp-image-526108\" srcset=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/06\/12113144\/image-175.png 448w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/06\/12113144\/image-175-300x81.png 300w\" sizes=\"auto, (max-width: 448px) 100vw, 448px\" \/><\/figure>\n\n\n\n<p><strong>Analisando a proporcionalidade: <\/strong>Quanto mais funcion\u00e1rios, mais se produz, ent\u00e3o:<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"446\" height=\"155\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/06\/12113217\/image-176.png\" alt=\"regra de tr\u00eas\" class=\"wp-image-526109\" srcset=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/06\/12113217\/image-176.png 446w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/06\/12113217\/image-176-300x104.png 300w\" sizes=\"auto, (max-width: 446px) 100vw, 446px\" \/><\/figure>\n\n\n\n<p>Assim,<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"138\" height=\"236\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/06\/12113311\/image-177.png\" alt=\"c\u00e1lculo\" class=\"wp-image-526110\"\/><\/figure>\n\n\n\n<p>Multiplicando em &#8220;X&#8221;:<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"304\" height=\"223\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/06\/12113346\/image-178.png\" alt=\"c\u00e1lculo\" class=\"wp-image-526111\" srcset=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/06\/12113346\/image-178.png 304w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/06\/12113346\/image-178-300x220.png 300w\" sizes=\"auto, (max-width: 304px) 100vw, 304px\" \/><\/figure>\n\n\n\n<p>Lembrando que queremos o <em>\u201cn\u00famero <strong>adicional<\/strong> de funcion\u00e1rios que a empresa deve contratar\u201d<\/em>, ent\u00e3o teremos que subtrair do total de funcion\u00e1rios os j\u00e1 existentes.<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"291\" height=\"110\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/06\/12113414\/image-179.png\" alt=\"c\u00e1lculo\" class=\"wp-image-526113\"\/><\/figure>\n\n\n\n<p><strong><span class=\"has-inline-color has-vivid-cyan-blue-color\">Alternativa E<\/span><\/strong><\/p>\n\n\n\n<p><strong>CESPE &#8211; Auxiliar Judici\u00e1rio\/2020<\/strong><\/p>\n\n\n\n<p><strong>Determinado equipamento \u00e9 capaz de digitalizar 1.800 p\u00e1ginas em 4 dias, funcionando 5 horas di\u00e1rias para esse fim. Nessa situa\u00e7\u00e3o, a quantidade de p\u00e1ginas que esse mesmo equipamento \u00e9 capaz de digitalizar em 3 dias, operando 4 horas e 30 minutos di\u00e1rios para esse fim, \u00e9 igual a:<\/strong><\/p>\n\n\n\n<p><strong>a) 2.666.<\/strong><\/p>\n\n\n\n<p><strong>b) 2.160.<\/strong><\/p>\n\n\n\n<p><strong>c) 1.215.<\/strong><\/p>\n\n\n\n<p><strong>d) 1.500.<\/strong><\/p>\n\n\n\n<p><strong>e) 1.161.<\/strong> <\/p>\n\n\n\n<p>Na primeira situa\u00e7\u00e3o (digitaliza\u00e7\u00e3o de 1.800 p\u00e1ginas), a equipe trabalha 20 horas (4 dias x 5 horas di\u00e1rias); j\u00e1 na segunda situa\u00e7\u00e3o, a equipe trabalhar\u00e1 13,5 horas (3 dias x 4,5 horas di\u00e1rias), assim:<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"448\" height=\"124\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/06\/12113500\/image-180.png\" alt=\"Regra de tr\u00eas \" class=\"wp-image-526115\" srcset=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/06\/12113500\/image-180.png 448w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/06\/12113500\/image-180-300x83.png 300w\" sizes=\"auto, (max-width: 448px) 100vw, 448px\" \/><\/figure>\n\n\n\n<p><strong><span class=\"has-inline-color has-luminous-vivid-amber-color\">Obs.<\/span><\/strong> 30 minutos \u00e9 metade de uma hora, ent\u00e3o podemos dizer que <strong>4 horas e 30 minutos <\/strong>\u00e9 equivalente a 4,5 horas. A conta \u00e9 simples, basta dividir os minutos por 60.<\/p>\n\n\n\n<p><strong>Analisando a proporcionalidade: <\/strong>Quanto mais p\u00e1ginas precisam ser digitalizadas, mais horas ser\u00e3o gastas.<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"448\" height=\"163\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/06\/12113543\/image-181.png\" alt=\"regra de tr\u00eas\" class=\"wp-image-526116\" srcset=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/06\/12113543\/image-181.png 448w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/06\/12113543\/image-181-300x109.png 300w\" sizes=\"auto, (max-width: 448px) 100vw, 448px\" \/><\/figure>\n\n\n\n<p>Agora \u00e9 s\u00f3 realizar o c\u00e1lculo:<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"189\" height=\"86\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/06\/12113604\/image-182.png\" alt=\"c\u00e1lculo\" class=\"wp-image-526117\"\/><\/figure>\n\n\n\n<p>Multiplicando em &#8220;X&#8221;:<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"297\" height=\"283\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/06\/12113634\/image-183.png\" alt=\"c\u00e1lculo\" class=\"wp-image-526118\"\/><\/figure>\n\n\n\n<p><strong><span class=\"has-inline-color has-vivid-cyan-blue-color\">Alternativa C<\/span><\/strong><\/p>\n\n\n\n<p>Vejamos agora a aplica\u00e7\u00e3o da <strong>regra de tr\u00eas<\/strong> <strong>composta <\/strong>com dois exerc\u00edcios de concurso.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-exemplos-de-regra-de-tres-composta\">Exemplos de <strong>regra de tr\u00eas composta<\/strong><\/h3>\n\n\n\n<p><strong>FCC &#8211; Auditor Fiscal de Manaus\/2019&nbsp;&nbsp;&nbsp;&nbsp;<\/strong><\/p>\n\n\n\n<p><strong>Se 3 pain\u00e9is solares fotovoltaicos produzem 70 kWh de energia em 50 dias, o n\u00famero de pain\u00e9is solares que produzem 112 kWh de energia em 15 dias \u00e9:<\/strong><\/p>\n\n\n\n<p><strong>a) 12.<\/strong><\/p>\n\n\n\n<p><strong>b) 15.<\/strong><\/p>\n\n\n\n<p><strong>c) 14.<\/strong><\/p>\n\n\n\n<p><strong>d) 16.<\/strong><\/p>\n\n\n\n<p><strong>e) 13.<\/strong><\/p>\n\n\n\n<p>Aplica\u00e7\u00e3o bem direta de uma regra de tr\u00eas composta, iniciaremos pela tabela:<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"613\" height=\"159\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/06\/12113822\/image-184.png\" alt=\"Regra de tr\u00eas \" class=\"wp-image-526121\" srcset=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/06\/12113822\/image-184.png 613w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/06\/12113822\/image-184-300x78.png 300w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/06\/12113822\/image-184-610x158.png 610w\" sizes=\"auto, (max-width: 613px) 100vw, 613px\" \/><\/figure>\n\n\n\n<p><strong>Analisando a proporcionalidade: <\/strong>Quanto mais pain\u00e9is, maior a produ\u00e7\u00e3o de energia e menor a quantidade de dias necess\u00e1rios para produ\u00e7\u00e3o, assim:<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"621\" height=\"164\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/06\/12113906\/image-185.png\" alt=\"regra de tr\u00eas\" class=\"wp-image-526122\" srcset=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/06\/12113906\/image-185.png 621w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/06\/12113906\/image-185-300x79.png 300w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/06\/12113906\/image-185-610x161.png 610w\" sizes=\"auto, (max-width: 621px) 100vw, 621px\" \/><\/figure>\n\n\n\n<p>Ent\u00e3o,<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"208\" height=\"87\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/06\/12113928\/image-186.png\" alt=\"c\u00e1lculo\" class=\"wp-image-526123\"\/><\/figure>\n\n\n\n<p><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-luminous-vivid-amber-color\"><strong>Obs.<\/strong> <\/mark>Note a invers\u00e3o da fra\u00e7\u00e3o da vari\u00e1vel \u201cDias\u201d.<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"245\" height=\"419\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/06\/12114000\/image-187.png\" alt=\"c\u00e1lculo\" class=\"wp-image-526125\" srcset=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/06\/12114000\/image-187.png 245w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/06\/12114000\/image-187-175x300.png 175w\" sizes=\"auto, (max-width: 245px) 100vw, 245px\" \/><\/figure>\n\n\n\n<p><strong>Alternativa D<\/strong><\/p>\n\n\n\n<p><strong>CESPE &#8211; Auditor-Fiscal SEFAZ RS\/2019<\/strong><\/p>\n\n\n\n<p><strong>Em uma f\u00e1brica de doces, 10 empregados igualmente eficientes, operando 3 m\u00e1quinas igualmente produtivas, produzem, em 8 horas por dia, 200 ovos de P\u00e1scoa. A demanda da f\u00e1brica aumentou para 425 ovos por dia. Em raz\u00e3o dessa demanda, a f\u00e1brica adquiriu mais uma m\u00e1quina, igual \u00e0s antigas, e contratou mais 5 empregados, t\u00e3o eficientes quanto os outros 10.<\/strong><\/p>\n\n\n\n<p><strong>Nessa situa\u00e7\u00e3o, para atender \u00e0 nova demanda, os 15 empregados, operando as 4 m\u00e1quinas, dever\u00e3o trabalhar durante<\/strong><\/p>\n\n\n\n<p><strong>a) 8 horas por dia.<\/strong><\/p>\n\n\n\n<p><strong>b) 8 horas e 30 minutos por dia.&nbsp; <\/strong><\/p>\n\n\n\n<p><strong>c) 8 horas e 50 minutos por dia.<\/strong><\/p>\n\n\n\n<p><strong>d) 9 horas e 30 minutos por dia.<\/strong><\/p>\n\n\n\n<p><strong>e) 9 horas e 50 minutos por dia.<\/strong><\/p>\n\n\n\n<p>Vamos montar nossa tabela:<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"797\" height=\"166\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/06\/12114038\/image-188.png\" alt=\"Regra de tr\u00eas \" class=\"wp-image-526128\" srcset=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/06\/12114038\/image-188.png 797w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/06\/12114038\/image-188-300x62.png 300w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/06\/12114038\/image-188-768x160.png 768w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/06\/12114038\/image-188-610x127.png 610w\" sizes=\"auto, (max-width: 797px) 100vw, 797px\" \/><\/figure>\n\n\n\n<p><strong>Analisando a proporcionalidade: <\/strong>Quanto mais empregados, menos m\u00e1quinas ser\u00e3o necess\u00e1rias, assim como menos horas precisar\u00e3o ser trabalhadas, al\u00e9m disso, h\u00e1 uma produ\u00e7\u00e3o de ovos maior, logo:<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"693\" height=\"144\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/06\/12114119\/image-189.png\" alt=\"Tabela de proporcionalidade\" class=\"wp-image-526129\" srcset=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/06\/12114119\/image-189.png 693w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/06\/12114119\/image-189-300x62.png 300w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/06\/12114119\/image-189-610x127.png 610w\" sizes=\"auto, (max-width: 693px) 100vw, 693px\" \/><\/figure>\n\n\n\n<p>Assim,<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"233\" height=\"75\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/06\/12114402\/image-190.png\" alt=\"C\u00e1lculo\" class=\"wp-image-526132\"\/><\/figure>\n\n\n\n<p>Agora vamos resolver:<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"295\" height=\"372\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/06\/12114431\/image-191.png\" alt=\"C\u00e1lculo\" class=\"wp-image-526133\" srcset=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/06\/12114431\/image-191.png 295w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/06\/12114431\/image-191-238x300.png 238w\" sizes=\"auto, (max-width: 295px) 100vw, 295px\" \/><\/figure>\n\n\n\n<p>E 8,5h \u00e9 equivalente a 8 horas e 30 minutos (0,5 x 60 = 30 min)<\/p>\n\n\n\n<p><strong><span class=\"has-inline-color has-vivid-cyan-blue-color\">Alternativa B<\/span><\/strong><\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-consideracoes-finais\">Considera\u00e7\u00f5es Finais<\/h2>\n\n\n\n<p>Caso ainda necessite de mais um refor\u00e7o, sugiro o <a href=\"https:\/\/www.estrategiaconcursos.com.br\/curso\/curso-basico-de-matematica-para-concursos-com-videoaulas-2020\/\" target=\"_blank\" rel=\"noreferrer noopener\">curso de matem\u00e1tica b\u00e1sica<\/a> aqui do Estrat\u00e9gia.<\/p>\n\n\n\n<p>Inclusive, h\u00e1 algumas aulas demonstrativas de regra de tr\u00eas excelentes, n\u00e3o deixe de conferir.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"162\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/06\/18090157\/image-277-1024x162.png\" alt=\"\" class=\"wp-image-528281\" srcset=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/06\/18090157\/image-277-1024x162.png 1024w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/06\/18090157\/image-277-300x47.png 300w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/06\/18090157\/image-277-768x122.png 768w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/06\/18090157\/image-277-610x97.png 610w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/06\/18090157\/image-277.png 1289w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>Muitas vezes nosso problema com matem\u00e1tica est\u00e1 na &#8220;base&#8221;, se for o caso, sugiro essa s\u00e9rie de v\u00eddeos &#8211; Matem\u00e1tica para iniciantes.<\/p>\n\n\n\n<p>\u00c9 isso a\u00ed, pessoal! Espero que o artigo de hoje tenha colaborado com seus estudos de <strong>regra de tr\u00eas<\/strong>. Nos vemos na pr\u00f3xima.<\/p>\n\n\n\n<p>Abra\u00e7o<\/p>\n\n\n\n<p class=\"has-text-align-center\"><em><strong>Assinatura Anual Ilimitada*<\/strong><\/em><\/p>\n\n\n\n<p class=\"has-text-align-center has-small-font-size\"><em>Prepare-se com o melhor material e com quem mais aprova em Concursos P\u00fablicos em todo o pa\u00eds. Assine agora a nossa Assinatura Anual e tenha acesso ilimitado* a todos os nossos cursos.<\/em><\/p>\n\n\n\n<p class=\"has-text-align-center has-luminous-vivid-amber-background-color has-background\"><strong>ASSINE AGORA<\/strong>&nbsp;\u2013&nbsp;<a href=\"https:\/\/www.estrategiaconcursos.com.br\/assinaturas\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Assinatura Ilimitada<\/strong><\/a><\/p>\n\n\n\n<p class=\"has-text-align-center\"><em><strong>Fique por dentro de todos os concursos<\/strong><\/em>:<\/p>\n\n\n\n<p class=\"has-text-align-center has-very-dark-gray-color has-text-color has-background\" style=\"background-color:#0792e3a6\"><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-abertos\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Concursos abertos<\/strong><\/a><\/p>\n\n\n\n<p class=\"has-text-align-center has-very-dark-gray-color has-text-color has-background\" style=\"background-color:#0792e38c\"><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-2023\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Concursos 2023<\/strong><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O artigo de hoje \u00e9 dedicado aos estudantes que t\u00eam dificuldades com matem\u00e1tica, em especial, com a regra de tr\u00eas simples e composta. Abordaremos o tema de forma bem pr\u00e1tica para facilitar seu aprendizado e garantir os pontos t\u00e3o preciosos na hora da prova. Vamos l\u00e1? O que \u00e9 uma regra de tr\u00eas? Regra de [&hellip;]<\/p>\n","protected":false},"author":741,"featured_media":531099,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"post_tipo":"article","footnotes":""},"categories":[2313,1,3766,1983,6741,2185,2017,1988,1981,1984],"tags":[],"tax_estado":[],"class_list":["post-526056","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-carreiras-bancarias","category-cursos-e-concursos","category-educacional","category-fiscal-estadual","category-forcas-armadas-oficiais","category-carreiras-juridicas","category-concursos-legislativos","category-policia","category-saude","category-tribunais"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.2 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Regra de tr\u00eas simples e composta - conceito e aplica\u00e7\u00e3o<\/title>\n<meta name=\"description\" content=\"Aprenda no artigo t\u00e9cnico de hoje tudo o que \u00e9 necess\u00e1rio para gabaritar as quest\u00f5es sobre regra de tr\u00eas simples e composta.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/regra-de-tres-simples-e-composta-conceito-e-aplicacao\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Regra de tr\u00eas simples e composta - conceito e aplica\u00e7\u00e3o\" \/>\n<meta property=\"og:description\" content=\"Aprenda no artigo t\u00e9cnico de hoje tudo o que \u00e9 necess\u00e1rio para gabaritar as quest\u00f5es sobre regra de tr\u00eas simples e composta.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/regra-de-tres-simples-e-composta-conceito-e-aplicacao\/\" \/>\n<meta property=\"og:site_name\" content=\"Estrat\u00e9gia Concursos\" \/>\n<meta property=\"article:published_time\" content=\"2020-07-09T21:33:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-10-07T14:19:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/06\/23171639\/aula-de-matematica-concurso-enem-gratuita-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"2127\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Brunno Lima\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:site\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Brunno Lima\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/regra-de-tres-simples-e-composta-conceito-e-aplicacao\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/regra-de-tres-simples-e-composta-conceito-e-aplicacao\/\"},\"author\":{\"name\":\"Brunno Lima\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/2865ec132c3404c9912015dd7a24eb1e\"},\"headline\":\"Regra de tr\u00eas simples e composta &#8211; conceito e aplica\u00e7\u00e3o\",\"datePublished\":\"2020-07-09T21:33:00+00:00\",\"dateModified\":\"2022-10-07T14:19:07+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/regra-de-tres-simples-e-composta-conceito-e-aplicacao\/\"},\"wordCount\":1403,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/regra-de-tres-simples-e-composta-conceito-e-aplicacao\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/06\/23171639\/aula-de-matematica-concurso-enem-gratuita-scaled.jpg\",\"articleSection\":[\"Banc\u00e1ria (BB, CEF e Bancos Estaduais)\",\"Concursos P\u00fablicos\",\"Educa\u00e7\u00e3o\",\"Fiscal - Estadual (ICMS)\",\"For\u00e7as Armadas (Oficiais)\",\"Jur\u00eddico\",\"Legislativo\",\"Policial (Agente, Escriv\u00e3o e Investigador)\",\"Sa\u00fade\",\"Tribunais\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/regra-de-tres-simples-e-composta-conceito-e-aplicacao\/#respond\"]}],\"copyrightYear\":\"2020\",\"copyrightHolder\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/regra-de-tres-simples-e-composta-conceito-e-aplicacao\/\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/regra-de-tres-simples-e-composta-conceito-e-aplicacao\/\",\"name\":\"Regra de tr\u00eas simples e composta - conceito e aplica\u00e7\u00e3o\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/regra-de-tres-simples-e-composta-conceito-e-aplicacao\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/regra-de-tres-simples-e-composta-conceito-e-aplicacao\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/06\/23171639\/aula-de-matematica-concurso-enem-gratuita-scaled.jpg\",\"datePublished\":\"2020-07-09T21:33:00+00:00\",\"dateModified\":\"2022-10-07T14:19:07+00:00\",\"description\":\"Aprenda no artigo t\u00e9cnico de hoje tudo o que \u00e9 necess\u00e1rio para gabaritar as quest\u00f5es sobre regra de tr\u00eas simples e composta.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/regra-de-tres-simples-e-composta-conceito-e-aplicacao\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/regra-de-tres-simples-e-composta-conceito-e-aplicacao\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/regra-de-tres-simples-e-composta-conceito-e-aplicacao\/#primaryimage\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/06\/23171639\/aula-de-matematica-concurso-enem-gratuita-scaled.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/06\/23171639\/aula-de-matematica-concurso-enem-gratuita-scaled.jpg\",\"width\":2560,\"height\":2127,\"caption\":\"Matem\u00e1tica para TJ-SP: Raz\u00e3o e Propor\u00e7\u00e3o\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/regra-de-tres-simples-e-composta-conceito-e-aplicacao\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Regra de tr\u00eas simples e composta &#8211; conceito e aplica\u00e7\u00e3o\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"name\":\"Estrat\u00e9gia Concursos\",\"description\":\"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.\",\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\",\"name\":\"Estrat\u00e9gia Concursos\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"width\":230,\"height\":60,\"caption\":\"Estrat\u00e9gia Concursos\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/EstratConcursos\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/2865ec132c3404c9912015dd7a24eb1e\",\"name\":\"Brunno Lima\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/d40b472e5e2856222d4a4a1c3ee2189ed7d7a9f67dc3343b880cc1889a7bd6af?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/d40b472e5e2856222d4a4a1c3ee2189ed7d7a9f67dc3343b880cc1889a7bd6af?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/d40b472e5e2856222d4a4a1c3ee2189ed7d7a9f67dc3343b880cc1889a7bd6af?s=96&d=mm&r=g\",\"caption\":\"Brunno Lima\"},\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/brunnoestrategiaconcursos-com-br\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Regra de tr\u00eas simples e composta - conceito e aplica\u00e7\u00e3o","description":"Aprenda no artigo t\u00e9cnico de hoje tudo o que \u00e9 necess\u00e1rio para gabaritar as quest\u00f5es sobre regra de tr\u00eas simples e composta.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.estrategiaconcursos.com.br\/blog\/regra-de-tres-simples-e-composta-conceito-e-aplicacao\/","og_locale":"pt_BR","og_type":"article","og_title":"Regra de tr\u00eas simples e composta - conceito e aplica\u00e7\u00e3o","og_description":"Aprenda no artigo t\u00e9cnico de hoje tudo o que \u00e9 necess\u00e1rio para gabaritar as quest\u00f5es sobre regra de tr\u00eas simples e composta.","og_url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/regra-de-tres-simples-e-composta-conceito-e-aplicacao\/","og_site_name":"Estrat\u00e9gia Concursos","article_published_time":"2020-07-09T21:33:00+00:00","article_modified_time":"2022-10-07T14:19:07+00:00","og_image":[{"width":2560,"height":2127,"url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/06\/23171639\/aula-de-matematica-concurso-enem-gratuita-scaled.jpg","type":"image\/jpeg"}],"author":"Brunno Lima","twitter_card":"summary_large_image","twitter_creator":"@EstratConcursos","twitter_site":"@EstratConcursos","twitter_misc":{"Escrito por":"Brunno Lima","Est. tempo de leitura":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/regra-de-tres-simples-e-composta-conceito-e-aplicacao\/#article","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/regra-de-tres-simples-e-composta-conceito-e-aplicacao\/"},"author":{"name":"Brunno Lima","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/2865ec132c3404c9912015dd7a24eb1e"},"headline":"Regra de tr\u00eas simples e composta &#8211; conceito e aplica\u00e7\u00e3o","datePublished":"2020-07-09T21:33:00+00:00","dateModified":"2022-10-07T14:19:07+00:00","mainEntityOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/regra-de-tres-simples-e-composta-conceito-e-aplicacao\/"},"wordCount":1403,"commentCount":0,"publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/regra-de-tres-simples-e-composta-conceito-e-aplicacao\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/06\/23171639\/aula-de-matematica-concurso-enem-gratuita-scaled.jpg","articleSection":["Banc\u00e1ria (BB, CEF e Bancos Estaduais)","Concursos P\u00fablicos","Educa\u00e7\u00e3o","Fiscal - Estadual (ICMS)","For\u00e7as Armadas (Oficiais)","Jur\u00eddico","Legislativo","Policial (Agente, Escriv\u00e3o e Investigador)","Sa\u00fade","Tribunais"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/regra-de-tres-simples-e-composta-conceito-e-aplicacao\/#respond"]}],"copyrightYear":"2020","copyrightHolder":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/regra-de-tres-simples-e-composta-conceito-e-aplicacao\/","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/regra-de-tres-simples-e-composta-conceito-e-aplicacao\/","name":"Regra de tr\u00eas simples e composta - conceito e aplica\u00e7\u00e3o","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/regra-de-tres-simples-e-composta-conceito-e-aplicacao\/#primaryimage"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/regra-de-tres-simples-e-composta-conceito-e-aplicacao\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/06\/23171639\/aula-de-matematica-concurso-enem-gratuita-scaled.jpg","datePublished":"2020-07-09T21:33:00+00:00","dateModified":"2022-10-07T14:19:07+00:00","description":"Aprenda no artigo t\u00e9cnico de hoje tudo o que \u00e9 necess\u00e1rio para gabaritar as quest\u00f5es sobre regra de tr\u00eas simples e composta.","breadcrumb":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/regra-de-tres-simples-e-composta-conceito-e-aplicacao\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/regra-de-tres-simples-e-composta-conceito-e-aplicacao\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/regra-de-tres-simples-e-composta-conceito-e-aplicacao\/#primaryimage","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/06\/23171639\/aula-de-matematica-concurso-enem-gratuita-scaled.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/06\/23171639\/aula-de-matematica-concurso-enem-gratuita-scaled.jpg","width":2560,"height":2127,"caption":"Matem\u00e1tica para TJ-SP: Raz\u00e3o e Propor\u00e7\u00e3o"},{"@type":"BreadcrumbList","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/regra-de-tres-simples-e-composta-conceito-e-aplicacao\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.estrategiaconcursos.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Regra de tr\u00eas simples e composta &#8211; conceito e aplica\u00e7\u00e3o"}]},{"@type":"WebSite","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","name":"Estrat\u00e9gia Concursos","description":"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.","publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization","name":"Estrat\u00e9gia Concursos","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","width":230,"height":60,"caption":"Estrat\u00e9gia Concursos"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/EstratConcursos"]},{"@type":"Person","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/2865ec132c3404c9912015dd7a24eb1e","name":"Brunno Lima","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/d40b472e5e2856222d4a4a1c3ee2189ed7d7a9f67dc3343b880cc1889a7bd6af?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/d40b472e5e2856222d4a4a1c3ee2189ed7d7a9f67dc3343b880cc1889a7bd6af?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d40b472e5e2856222d4a4a1c3ee2189ed7d7a9f67dc3343b880cc1889a7bd6af?s=96&d=mm&r=g","caption":"Brunno Lima"},"url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/brunnoestrategiaconcursos-com-br\/"}]}},"_links":{"self":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/526056","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/users\/741"}],"replies":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/comments?post=526056"}],"version-history":[{"count":18,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/526056\/revisions"}],"predecessor-version":[{"id":1106344,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/526056\/revisions\/1106344"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media\/531099"}],"wp:attachment":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media?parent=526056"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/categories?post=526056"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tags?post=526056"},{"taxonomy":"tax_estado","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tax_estado?post=526056"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}