{"id":523193,"date":"2020-06-05T16:50:56","date_gmt":"2020-06-05T19:50:56","guid":{"rendered":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?p=523193"},"modified":"2020-06-05T20:54:11","modified_gmt":"2020-06-05T23:54:11","slug":"sefaz-rr-saiba-tudo-sobre-o-proximo-concurso","status":"publish","type":"post","link":"https:\/\/www.estrategiaconcursos.com.br\/blog\/sefaz-rr-saiba-tudo-sobre-o-proximo-concurso\/","title":{"rendered":"SEFAZ RR: Saiba tudo sobre o pr\u00f3ximo concurso!"},"content":{"rendered":"\n<p class=\"has-text-align-left\">Ol\u00e1, pessoal! Tudo bem com voc\u00ea? Sou o <span style=\"color:#0300a3\" class=\"has-inline-color\"><strong>Professor Eduardo da Rocha<\/strong><\/span>, Auditor Fiscal do Tesouro Estadual de Pernambuco, e venho nesse texto trazer tudo que voc\u00ea precisa saber sobre o concurso da SEFAZ de Roraima!<\/p>\n\n\n\n<p>Sem publicar edital h\u00e1 13 anos, a Secretaria de Estado da Fazenda do Roraima deve realizar um novo concurso p\u00fablico em breve.&nbsp;<\/p>\n\n\n\n<p><strong><span style=\"color:#0d00a3\" class=\"has-inline-color\">O c<\/span><span style=\"color:#0800a3\" class=\"has-inline-color\">argo e as altera\u00e7\u00f5es na LC 8\/94<\/span><\/strong><\/p>\n\n\n\n<p>A Lei Complementar 8\/94 disp\u00f5e sobre a Organiza\u00e7\u00e3o da Carreira do Fisco Estadual &#8211; Grupo Tributa\u00e7\u00e3o, Arrecada\u00e7\u00e3o e Fiscaliza\u00e7\u00e3o (TAF).&nbsp;<\/p>\n\n\n\n<p>Essa lei dividia o TAF em 2 cargos:<\/p>\n\n\n\n<p>I &#8211;&nbsp;<strong><span class=\"has-inline-color has-vivid-red-color\">Fiscal<\/span><\/strong>&nbsp;de Tributos Estaduais &#8211; FTE; e&nbsp;<\/p>\n\n\n\n<p>II \u2013&nbsp;<strong><span class=\"has-inline-color has-vivid-red-color\">T\u00e9cnico<\/span><\/strong>&nbsp;de Tributos Estaduais \u2013 TTE.<\/p>\n\n\n\n<p>Os cargos eram organizados em carreira, distribu\u00eddos em quatro n\u00edveis, na forma seguinte:&nbsp;<\/p>\n\n\n\n<p>I &#8211; Fiscal de Tributos Estaduais &#8211; FTE:&nbsp;<\/p>\n\n\n\n<p>a) N\u00edvel 1 &#8211; 40 cargos<\/p>\n\n\n\n<p>b) N\u00edvel 2 &#8211; 40 cargos<\/p>\n\n\n\n<p>c) N\u00edvel 3 &#8211; 40 cargos<\/p>\n\n\n\n<p>d) N\u00edvel Especial &#8211; 40 cargos<\/p>\n\n\n\n<p>II &#8211; T\u00e9cnico de Tributos Estaduais &#8211; TTE:&nbsp;<\/p>\n\n\n\n<p>a) N\u00edvel 1 &#8211; 60 cargos&nbsp;<\/p>\n\n\n\n<p>b) N\u00edvel 2 &#8211; 60 cargos<\/p>\n\n\n\n<p>c) N\u00edvel 3 &#8211; 60 cargos.<\/p>\n\n\n\n<p>d) N\u00edvel Especial &#8211; 60 cargos&nbsp;<\/p>\n\n\n\n<p>Vejamos agora a escolaridade exigida:<\/p>\n\n\n\n<p>\u201cArt. 9\u00ba &#8211; S\u00e3o requisitos para inscri\u00e7\u00e3o no concurso:<\/p>\n\n\n\n<p>III- ter conclu\u00eddo curso de n\u00edvel superior reconhecido oficialmente, nas \u00e1reas de Administra\u00e7\u00e3o, Economia, Direito e Ci\u00eancias Cont\u00e1beis, para os cargos de FTE;&nbsp;<\/p>\n\n\n\n<p>IV &#8211; Ter conclu\u00eddo o segundo grau ou equivalente, para os cargos de TTE;\u201d<\/p>\n\n\n\n<p>Perceba que o cargo de Fiscal (FTE) s\u00f3 permitia a ocupa\u00e7\u00e3o por aqueles com forma\u00e7\u00e3o espec\u00edfica nas \u00e1reas de Administra\u00e7\u00e3o, Economia, Direito e Ci\u00eancias Cont\u00e1beis. Por isso que se voc\u00ea abrir o \u00faltimo edital ver\u00e1 a necessidade de forma\u00e7\u00e3o espec\u00edficas nessas \u00e1reas!<\/p>\n\n\n\n<p>Para o cargo de T\u00e9cnico (TTE), exigia-se apenas o n\u00edvel m\u00e9dio, antigo segundo grau.<\/p>\n\n\n\n<p>Entretanto a LC 270 de 2018 alterou de maneira significativa a LC 8\/94 e&nbsp;<strong><span class=\"has-inline-color has-vivid-red-color\">o cargo Fiscal de Tributos Estaduais passou a se chamar Auditor<\/span><\/strong>&nbsp;Fiscal de Tributos Estaduais \u2013 AFTE.<\/p>\n\n\n\n<p><strong><span class=\"has-inline-color has-vivid-red-color\">Uma outra importante altera\u00e7\u00e3o \u00e9 a exig\u00eancia de n\u00edvel superior em q<\/span><\/strong><span class=\"has-inline-color has-vivid-red-color\"><strong>ualquer \u00e1rea, tanto para Auditores (antigos Fiscais) como para T\u00e9cnicos, que antes s\u00f3 se exigia o n\u00edvel m\u00e9dio<\/strong>.<\/span><\/p>\n\n\n\n<p><strong><span style=\"color:#0300a3\" class=\"has-inline-color\">Remunera\u00e7\u00e3o e jornada de trabalho&nbsp;<\/span><\/strong><\/p>\n\n\n\n<p><strong><span class=\"has-inline-color has-vivid-red-color\">A remunera\u00e7\u00e3o dos Auditores da SEFAZ-RR \u00e9 a mais alta dentre os Fiscos do pa\u00eds!<\/span>&nbsp;<\/strong>Trata-se de uma motiva\u00e7\u00e3o e tanto!&nbsp;<\/p>\n\n\n\n<p>Os auditores ter\u00e3o direito a perceber, al\u00e9m do vencimento, as seguintes vantagens pecuni\u00e1rias:&nbsp;<\/p>\n\n\n\n<p>I &#8211; gratifica\u00e7\u00e3o de est\u00edmulo \u00e0 produtividade;<\/p>\n\n\n\n<p>II &#8211; honor\u00e1rios:<\/p>\n\n\n\n<p>a) pelo exerc\u00edcio de atividades auxiliares ou membro de banca ou comiss\u00e3o de concurso p\u00fablico ou de acesso, na Secretaria de Estado da Fazenda;<\/p>\n\n\n\n<p>b) pelo exerc\u00edcio do magist\u00e9rio ou de fun\u00e7\u00f5es auxiliares em programas de desenvolvimento de recursos humanos, de interesse da Secretaria de Estado da Fazenda;<\/p>\n\n\n\n<p>c) pela elabora\u00e7\u00e3o de trabalhos t\u00e9cnicos e especiais, aprovados pelo Secret\u00e1rio de Estado da Fazenda, desde que n\u00e3o correspondam \u00e0s atribui\u00e7\u00f5es do cargo ocupado;&nbsp;<\/p>\n\n\n\n<p>III &#8211; adicional de tempo de servi\u00e7o (1% ao ano);<\/p>\n\n\n\n<p>IV &#8211; ajuda de custo;<\/p>\n\n\n\n<p>V \u2013 di\u00e1ria;<\/p>\n\n\n\n<p>VI \u2013 13\u00ba sal\u00e1rio;&nbsp;<\/p>\n\n\n\n<p>VIII &#8211; adicional pelo exerc\u00edcio em regi\u00f5es in\u00f3spitas, em valor correspondente at\u00e9 50% do seu vencimento;&nbsp;<\/p>\n\n\n\n<p>IX &#8211; adicional por risco de vida, pelo exerc\u00edcio da fun\u00e7\u00e3o de fiscaliza\u00e7\u00e3o de mercadorias em tr\u00e2nsito e fiscaliza\u00e7\u00e3o especial, nos termos da legisla\u00e7\u00e3o tribut\u00e1ria em vigor, no valor correspondente a 40% do seu vencimento;&nbsp;<\/p>\n\n\n\n<p>X &#8211; indeniza\u00e7\u00e3o de transporte pela utiliza\u00e7\u00e3o de meio pr\u00f3prio de locomo\u00e7\u00e3o para a execu\u00e7\u00e3o de servi\u00e7os externos, em valor correspondente a 12% do seu vencimento.&nbsp;<\/p>\n\n\n\n<p>XI &#8211; outras vantagens concedidas em Lei.<\/p>\n\n\n\n<p>Somando tudo isso chegamos a um \u00f3timo sal\u00e1rio! Veja abaixo um exemplo de remunera\u00e7\u00e3o retirado do Portal da Transpar\u00eancia.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"580\" height=\"309\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/06\/05164921\/image-71.png\" alt=\"\" class=\"wp-image-523218\" srcset=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/06\/05164921\/image-71.png 580w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/06\/05164921\/image-71-300x160.png 300w\" sizes=\"auto, (max-width: 580px) 100vw, 580px\" \/><\/figure><\/div>\n\n\n\n<p>A jornada de trabalho \u00e9 de 40 horas semanais, havendo tamb\u00e9m o regime de escala de 5 por 11, a depender da sua lota\u00e7\u00e3o. Com esse regime \u00e9 poss\u00edvel que voc\u00ea more no seu Estado e trabalha em Roraima, sendo uma \u00f3tima oportunidade para quem quer ganhar bem, morar na sua cidade de origem e ainda ter tempo para se dedicar a uma outra atividade.<\/p>\n\n\n\n<p><strong><span style=\"color:#0300a3\" class=\"has-inline-color\">Atribui\u00e7\u00f5es do Auditor<\/span><\/strong><\/p>\n\n\n\n<p>O Fiscal de Tributos Estaduais \u00e9 a autoridade administrativa competente para, privativamente, exercer a fiscaliza\u00e7\u00e3o e efetuar o lan\u00e7amento dos tributos estaduais. Dentre outras, possui as seguintes atribui\u00e7\u00f5es.<\/p>\n\n\n\n<p>a) lavrar termos, intima\u00e7\u00f5es, notifica\u00e7\u00f5es de lan\u00e7amento, auto de infra\u00e7\u00e3o e auto de apreens\u00e3o;&nbsp;<\/p>\n\n\n\n<p>b) examinar bens m\u00f3veis e im\u00f3veis, mercadorias, documentos e livros fiscais, comerciais e arquivos do sujeito passivo da obriga\u00e7\u00e3o tribut\u00e1ria;&nbsp;<\/p>\n\n\n\n<p>c) emitir parecer em processos de consulta e de regime especial, bem como de extin\u00e7\u00e3o, suspens\u00e3o e exclus\u00e3o de cr\u00e9dito tribut\u00e1rio, ressalvada a compet\u00eancia da Procuradoria Geral do Estado;&nbsp;<\/p>\n\n\n\n<p>d) praticar outros atos indicados na legisla\u00e7\u00e3o;&nbsp;<\/p>\n\n\n\n<p>e) executar atividades de fiscaliza\u00e7\u00e3o de mercadorias em tr\u00e2nsito, em terminal de passageiro e de cargas, postos fiscais situados em rodovias e nas fronteiras do Estado e em grupos volantes, em regime de plant\u00e3o, inclusive aos s\u00e1bados, domingos e feriados.&nbsp;<\/p>\n\n\n\n<p><strong><span style=\"color:#0300a3\" class=\"has-inline-color\">Mat\u00e9rias exigidas<\/span><\/strong><\/p>\n\n\n\n<p>Diferentemente de outros Estados, a LC 8\/94 previu em seu art. 13 um conjunto de mat\u00e9rias que devem obrigatoriamente estar presentes no Concurso de Auditor (antigo Fiscal). S\u00e3o elas:&nbsp;<br \/><\/p>\n\n\n\n<p>a) Direito Tribut\u00e1rio<\/p>\n\n\n\n<p>b) Legisla\u00e7\u00e3o Tribut\u00e1ria<\/p>\n\n\n\n<p>c) Direito Constitucional<\/p>\n\n\n\n<p>d) Direito Administrativo<\/p>\n\n\n\n<p>e) Direito Civil<\/p>\n\n\n\n<p>f) Direito Penal&nbsp;<\/p>\n\n\n\n<p>g) Direito Empresarial<\/p>\n\n\n\n<p>h) Contabilidade Geral<\/p>\n\n\n\n<p>i) Contabilidade Comercial (como se chamava a parte da contabilidade que se referia a opera\u00e7\u00f5es com mercadorias)<\/p>\n\n\n\n<p>j) Contabilidade de custos&nbsp;<\/p>\n\n\n\n<p>k) Contabilidade P\u00fablica;<\/p>\n\n\n\n<p>l) Economia<\/p>\n\n\n\n<p>m) Matem\u00e1tica<\/p>\n\n\n\n<p>n) Estat\u00edstica<\/p>\n\n\n\n<p>o) Portugu\u00eas<\/p>\n\n\n\n<p>p) Administra\u00e7\u00e3o P\u00fablica<\/p>\n\n\n\n<p>Em tese novas mat\u00e9rias podem ser acrescentadas mas para que algumas das listadas acima n\u00e3o esteja no seu edital \u00e9 necess\u00e1ria uma lei alterando a LC 8\/94.<\/p>\n\n\n\n<p><strong><span style=\"color:#0300a3\" class=\"has-inline-color\">Comiss\u00e3o formada<\/span><\/strong><\/p>\n\n\n\n<p>No&nbsp;dia 9 de setembro de 2016, foi publicada a&nbsp;Portaria&nbsp;n\u00ba 836\/2016 no Di\u00e1rio Oficial do Estado de Roraima,&nbsp;criando a comiss\u00e3o de estudo para viabilidade de concurso p\u00fablico em atendimento \u00e0 demanda do grupo TAF. Apesar de&nbsp;constatada a necessidade imediata&nbsp;\u00e0 \u00e9poca&nbsp;de cinco vagas mais 28 para contrata\u00e7\u00f5es futuras em at\u00e9 quatro anos, o concurso n\u00e3o avan\u00e7ou.&nbsp;<\/p>\n\n\n\n<p>Em&nbsp;29 de maio de 2020&nbsp;foi publicada&nbsp;a Portaria n\u00ba 35, que&nbsp;novamente&nbsp;constitui a comiss\u00e3o de trabalho para realiza\u00e7\u00e3o de concurso p\u00fablico visando o preenchimento do quadro de&nbsp;agora&nbsp;Auditores Fiscais de Tributos Estaduais da Secretaria de Estado da Fazenda.<\/p>\n\n\n\n<p>O grupo \u00e9 formado por tr\u00eas servidores, onde os mesmos ter\u00e3o que apresentar, no prazo de 90 dias, uma an\u00e1lise da necessidade de pessoal do cargo de Auditor.&nbsp;Por isso hoje ainda n\u00e3o sabemos quantas vagas teremos no pr\u00f3ximo certame.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"228\" height=\"325\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/06\/05164407\/image-70.png\" alt=\"\" class=\"wp-image-523214\" srcset=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/06\/05164407\/image-70.png 228w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/06\/05164407\/image-70-210x300.png 210w\" sizes=\"auto, (max-width: 228px) 100vw, 228px\" \/><\/figure><\/div>\n\n\n\n<p><\/p>\n\n\n\n<p><strong><span style=\"color:#0800a3\" class=\"has-inline-color\">O \u00faltimo concurso&nbsp;<\/span><\/strong><\/p>\n\n\n\n<p>O \u00faltimo concurso para o grupo TAF foi em 2006, organizado pela CETAP e realizado somente na cidade de Boa Vista-RR. \u00c0 \u00e9poca o cargo ainda era chamado de Fiscal e exigia-se forma\u00e7\u00e3o espec\u00edfica nas \u00e1reas que mencionamos. Foram disponibilizadas 30 vagas.<\/p>\n\n\n\n<p>O concurso foi realizado em duas etapas:&nbsp;<\/p>\n\n\n\n<p>1\u00aa) Prova Objetiva das mat\u00e9rias listada na lei 8\/94, contendo 60 quest\u00f5es de m\u00faltipla escolha com 5 alternativas cada; e<\/p>\n\n\n\n<p>2\u00aa) Curso de Forma\u00e7\u00e3o, de car\u00e1ter eliminat\u00f3rio e classificat\u00f3rio.<\/p>\n\n\n\n<p>As mat\u00e9rias foram divididas em 2 blocos: Conhecimentos Espec\u00edficos, que continha Legisla\u00e7\u00e3o Tribut\u00e1ria e Direito Tribut\u00e1rio, e Conhecimentos Gerais, que continha as demais mat\u00e9rias. Para n\u00e3o ser eliminado era necess\u00e1ria uma pontua\u00e7\u00e3o m\u00ednima de 30 pontos. A pontua\u00e7\u00e3o m\u00e1xima da prova era de 100 pontos e, como foram 60 quest\u00f5es, t\u00ednhamos pesos diferentes entre elas. Veja a distribui\u00e7\u00e3o e os pesos aplicados:<\/p>\n\n\n\n<figure class=\"wp-block-table\"><table><tbody><tr><td class=\"has-text-align-center\" data-align=\"center\"><strong>Disciplinas<\/strong><\/td><td class=\"has-text-align-center\" data-align=\"center\"><strong>Quest\u00f5es<\/strong><\/td><td class=\"has-text-align-center\" data-align=\"center\"><strong>Peso<\/strong><\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">L\u00edngua Portuguesa<\/td><td class=\"has-text-align-center\" data-align=\"center\">10<\/td><td class=\"has-text-align-center\" data-align=\"center\">1,0<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">Conhecimentos Gerais<\/td><td class=\"has-text-align-center\" data-align=\"center\">25<\/td><td class=\"has-text-align-center\" data-align=\"center\">1,6<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">Conhecimentos Espec\u00edficos<\/td><td class=\"has-text-align-center\" data-align=\"center\">25<\/td><td class=\"has-text-align-center\" data-align=\"center\">2,0<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<p>O Curso de Forma\u00e7\u00e3o teve carga hor\u00e1ria de 88 horas em regime de tempo integral, podendo as atividades do referido curso serem realizadas em hor\u00e1rio diurno e\/ou noturno, inclusive aos s\u00e1bados.<\/p>\n\n\n\n<p>Foi eliminado do Curso de Forma\u00e7\u00e3o e Treinamento aquele que n\u00e3o frequentou no m\u00ednimo 80% das horas das atividades e\/ou n\u00e3o satisfez as demais disposi\u00e7\u00f5es descritas em Regulamento.<\/p>\n\n\n\n<p>A nota final de aprova\u00e7\u00e3o do treinamento da 2\u00aa etapa do Concurso correspondeu \u00e0 m\u00e9dia aritm\u00e9tica das cinco avalia\u00e7\u00f5es nas \u00e1reas da forma\u00e7\u00e3o espec\u00edfica, sendo igual ou superior a 7 pontos, na escala de 0 a 10, sem atribui\u00e7\u00e3o de pesos.<\/p>\n\n\n\n<p>Foi eliminado aquele que n\u00e3o obteve nota igual ou superior a 5 pontos em cada avalia\u00e7\u00e3o espec\u00edfica independentemente de ter alcan\u00e7ado a m\u00e9dia 7.<\/p>\n\n\n\n<p class=\"has-background has-text-align-center has-very-light-gray-background-color\"><strong>Mais informa\u00e7\u00f5es: <a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-sefaz-rr\/\" target=\"_blank\" rel=\"noreferrer noopener\">Concurso Sefaz RR<\/a><\/strong><\/p>\n\n\n\n<p>\u00c9 isso, pessoal!&nbsp;<\/p>\n\n\n\n<p>Instagram: @profeduardodarocha<\/p>\n\n\n\n<p>Facebook: \/profeduardodarocha<\/p>\n\n\n\n<p>Youtube:&nbsp;<a href=\"https:\/\/www.youtube.com\/profeduardodarocha\">https:\/\/www.youtube.com\/profeduardodarocha<\/a><\/p>\n\n\n\n<p>Pacote completo \u2013 SEFAZ RR:<\/p>\n\n\n\n<p><a href=\"https:\/\/www.estrategiaconcursos.com.br\/curso\/pacote-completo-p-sefaz-rr-fiscal-de-tributos-com-videoaulas-2020\/\">https:\/\/www.estrategiaconcursos.com.br\/curso\/pacote-completo-p-sefaz-rr-fiscal-de-tributos-com-videoaulas-2020\/<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ol\u00e1, pessoal! Tudo bem com voc\u00ea? Sou o Professor Eduardo da Rocha, Auditor Fiscal do Tesouro Estadual de Pernambuco, e venho nesse texto trazer tudo que voc\u00ea precisa saber sobre o concurso da SEFAZ de Roraima! Sem publicar edital h\u00e1 13 anos, a Secretaria de Estado da Fazenda do Roraima deve realizar um novo concurso [&hellip;]<\/p>\n","protected":false},"author":442,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"post_tipo":"article","footnotes":""},"categories":[1,1983],"tags":[],"tax_estado":[],"class_list":["post-523193","post","type-post","status-publish","format-standard","hentry","category-cursos-e-concursos","category-fiscal-estadual"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.2 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>SEFAZ RR: Saiba tudo sobre o pr\u00f3ximo concurso!<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/sefaz-rr-saiba-tudo-sobre-o-proximo-concurso\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"SEFAZ RR: Saiba tudo sobre o pr\u00f3ximo concurso!\" \/>\n<meta property=\"og:description\" content=\"Ol\u00e1, pessoal! Tudo bem com voc\u00ea? Sou o Professor Eduardo da Rocha, Auditor Fiscal do Tesouro Estadual de Pernambuco, e venho nesse texto trazer tudo que voc\u00ea precisa saber sobre o concurso da SEFAZ de Roraima! Sem publicar edital h\u00e1 13 anos, a Secretaria de Estado da Fazenda do Roraima deve realizar um novo concurso [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/sefaz-rr-saiba-tudo-sobre-o-proximo-concurso\/\" \/>\n<meta property=\"og:site_name\" content=\"Estrat\u00e9gia Concursos\" \/>\n<meta property=\"article:published_time\" content=\"2020-06-05T19:50:56+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-06-05T23:54:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-content\/uploads\/2020\/06\/image-71.png\" \/>\n<meta name=\"author\" content=\"Eduardo Da Rocha\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:site\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Eduardo Da Rocha\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/sefaz-rr-saiba-tudo-sobre-o-proximo-concurso\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/sefaz-rr-saiba-tudo-sobre-o-proximo-concurso\/\"},\"author\":{\"name\":\"Eduardo Da Rocha\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/72dcc3ee857256affea7a386e5ab8d95\"},\"headline\":\"SEFAZ RR: Saiba tudo sobre o pr\u00f3ximo concurso!\",\"datePublished\":\"2020-06-05T19:50:56+00:00\",\"dateModified\":\"2020-06-05T23:54:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/sefaz-rr-saiba-tudo-sobre-o-proximo-concurso\/\"},\"wordCount\":1555,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/sefaz-rr-saiba-tudo-sobre-o-proximo-concurso\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-content\/uploads\/2020\/06\/image-71.png\",\"articleSection\":[\"Concursos P\u00fablicos\",\"Fiscal - Estadual (ICMS)\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/sefaz-rr-saiba-tudo-sobre-o-proximo-concurso\/#respond\"]}],\"copyrightYear\":\"2020\",\"copyrightHolder\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/sefaz-rr-saiba-tudo-sobre-o-proximo-concurso\/\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/sefaz-rr-saiba-tudo-sobre-o-proximo-concurso\/\",\"name\":\"SEFAZ RR: Saiba tudo sobre o pr\u00f3ximo concurso!\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/sefaz-rr-saiba-tudo-sobre-o-proximo-concurso\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/sefaz-rr-saiba-tudo-sobre-o-proximo-concurso\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-content\/uploads\/2020\/06\/image-71.png\",\"datePublished\":\"2020-06-05T19:50:56+00:00\",\"dateModified\":\"2020-06-05T23:54:11+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/sefaz-rr-saiba-tudo-sobre-o-proximo-concurso\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/sefaz-rr-saiba-tudo-sobre-o-proximo-concurso\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/sefaz-rr-saiba-tudo-sobre-o-proximo-concurso\/#primaryimage\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/06\/05164921\/image-71.png\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/06\/05164921\/image-71.png\",\"width\":580,\"height\":309},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/sefaz-rr-saiba-tudo-sobre-o-proximo-concurso\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"SEFAZ RR: Saiba tudo sobre o pr\u00f3ximo concurso!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"name\":\"Estrat\u00e9gia Concursos\",\"description\":\"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.\",\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\",\"name\":\"Estrat\u00e9gia Concursos\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"width\":230,\"height\":60,\"caption\":\"Estrat\u00e9gia Concursos\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/EstratConcursos\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/72dcc3ee857256affea7a386e5ab8d95\",\"name\":\"Eduardo Da Rocha\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/dc38a9509db389e7f37ec942aa45a2cdcc18df4d080e47bc2e407cc634ca1a14?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/dc38a9509db389e7f37ec942aa45a2cdcc18df4d080e47bc2e407cc634ca1a14?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/dc38a9509db389e7f37ec942aa45a2cdcc18df4d080e47bc2e407cc634ca1a14?s=96&d=mm&r=g\",\"caption\":\"Eduardo Da Rocha\"},\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/eduardodarochaestrategiaconcursos-com-br\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"SEFAZ RR: Saiba tudo sobre o pr\u00f3ximo concurso!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.estrategiaconcursos.com.br\/blog\/sefaz-rr-saiba-tudo-sobre-o-proximo-concurso\/","og_locale":"pt_BR","og_type":"article","og_title":"SEFAZ RR: Saiba tudo sobre o pr\u00f3ximo concurso!","og_description":"Ol\u00e1, pessoal! Tudo bem com voc\u00ea? Sou o Professor Eduardo da Rocha, Auditor Fiscal do Tesouro Estadual de Pernambuco, e venho nesse texto trazer tudo que voc\u00ea precisa saber sobre o concurso da SEFAZ de Roraima! Sem publicar edital h\u00e1 13 anos, a Secretaria de Estado da Fazenda do Roraima deve realizar um novo concurso [&hellip;]","og_url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/sefaz-rr-saiba-tudo-sobre-o-proximo-concurso\/","og_site_name":"Estrat\u00e9gia Concursos","article_published_time":"2020-06-05T19:50:56+00:00","article_modified_time":"2020-06-05T23:54:11+00:00","og_image":[{"url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-content\/uploads\/2020\/06\/image-71.png","type":"","width":"","height":""}],"author":"Eduardo Da Rocha","twitter_card":"summary_large_image","twitter_creator":"@EstratConcursos","twitter_site":"@EstratConcursos","twitter_misc":{"Escrito por":"Eduardo Da Rocha","Est. tempo de leitura":"8 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/sefaz-rr-saiba-tudo-sobre-o-proximo-concurso\/#article","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/sefaz-rr-saiba-tudo-sobre-o-proximo-concurso\/"},"author":{"name":"Eduardo Da Rocha","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/72dcc3ee857256affea7a386e5ab8d95"},"headline":"SEFAZ RR: Saiba tudo sobre o pr\u00f3ximo concurso!","datePublished":"2020-06-05T19:50:56+00:00","dateModified":"2020-06-05T23:54:11+00:00","mainEntityOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/sefaz-rr-saiba-tudo-sobre-o-proximo-concurso\/"},"wordCount":1555,"commentCount":0,"publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/sefaz-rr-saiba-tudo-sobre-o-proximo-concurso\/#primaryimage"},"thumbnailUrl":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-content\/uploads\/2020\/06\/image-71.png","articleSection":["Concursos P\u00fablicos","Fiscal - Estadual (ICMS)"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/sefaz-rr-saiba-tudo-sobre-o-proximo-concurso\/#respond"]}],"copyrightYear":"2020","copyrightHolder":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/sefaz-rr-saiba-tudo-sobre-o-proximo-concurso\/","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/sefaz-rr-saiba-tudo-sobre-o-proximo-concurso\/","name":"SEFAZ RR: Saiba tudo sobre o pr\u00f3ximo concurso!","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/sefaz-rr-saiba-tudo-sobre-o-proximo-concurso\/#primaryimage"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/sefaz-rr-saiba-tudo-sobre-o-proximo-concurso\/#primaryimage"},"thumbnailUrl":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-content\/uploads\/2020\/06\/image-71.png","datePublished":"2020-06-05T19:50:56+00:00","dateModified":"2020-06-05T23:54:11+00:00","breadcrumb":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/sefaz-rr-saiba-tudo-sobre-o-proximo-concurso\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/sefaz-rr-saiba-tudo-sobre-o-proximo-concurso\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/sefaz-rr-saiba-tudo-sobre-o-proximo-concurso\/#primaryimage","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/06\/05164921\/image-71.png","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/06\/05164921\/image-71.png","width":580,"height":309},{"@type":"BreadcrumbList","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/sefaz-rr-saiba-tudo-sobre-o-proximo-concurso\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.estrategiaconcursos.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"SEFAZ RR: Saiba tudo sobre o pr\u00f3ximo concurso!"}]},{"@type":"WebSite","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","name":"Estrat\u00e9gia Concursos","description":"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.","publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization","name":"Estrat\u00e9gia Concursos","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","width":230,"height":60,"caption":"Estrat\u00e9gia Concursos"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/EstratConcursos"]},{"@type":"Person","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/72dcc3ee857256affea7a386e5ab8d95","name":"Eduardo Da Rocha","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/dc38a9509db389e7f37ec942aa45a2cdcc18df4d080e47bc2e407cc634ca1a14?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/dc38a9509db389e7f37ec942aa45a2cdcc18df4d080e47bc2e407cc634ca1a14?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/dc38a9509db389e7f37ec942aa45a2cdcc18df4d080e47bc2e407cc634ca1a14?s=96&d=mm&r=g","caption":"Eduardo Da Rocha"},"url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/eduardodarochaestrategiaconcursos-com-br\/"}]}},"_links":{"self":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/523193","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/users\/442"}],"replies":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/comments?post=523193"}],"version-history":[{"count":3,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/523193\/revisions"}],"predecessor-version":[{"id":523322,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/523193\/revisions\/523322"}],"wp:attachment":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media?parent=523193"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/categories?post=523193"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tags?post=523193"},{"taxonomy":"tax_estado","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tax_estado?post=523193"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}