{"id":520977,"date":"2020-06-18T12:30:00","date_gmt":"2020-06-18T15:30:00","guid":{"rendered":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?p=520977"},"modified":"2023-07-06T15:16:44","modified_gmt":"2023-07-06T18:16:44","slug":"saiba-como-participar-do-leilao-da-receita-federal","status":"publish","type":"post","link":"https:\/\/www.estrategiaconcursos.com.br\/blog\/saiba-como-participar-do-leilao-da-receita-federal\/","title":{"rendered":"Saiba como participar do  leil\u00e3o da Receita Federal."},"content":{"rendered":"\n<p class=\"has-medium-font-size\"><em>J\u00e1 pensou em comprar eletr\u00f4nicos e at\u00e9 mesmo carros por menos da metade do pre\u00e7o? E o melhor: de maneira totalmente legal. Ent\u00e3o saiba mais sobre como funciona o <strong>leil\u00e3o da receita federal<\/strong>.<\/em><\/p>\n\n\n\n<p>Ol\u00e1, estrategista. Tudo joia?<\/p>\n\n\n\n<p>Ficou interessado, n\u00e3o \u00e9? Ali\u00e1s, quem n\u00e3o gostaria de comprar produtos de alta qualidade, com alto valor agregado, por um pre\u00e7o bastante acess\u00edvel? E n\u00e3o estamos nos referindo a nenhuma pr\u00e1tica ilegal, uma vez que o \u201cvendedor\u201d destes produtos \u00e9 o pr\u00f3prio Estado.<\/p>\n\n\n\n<p>Antes de adentrarmos no leil\u00e3o da receita federal propriamente dito, vamos entender melhor os motivos destes produtos, muitos deles ainda lacrados, serem vendidos por pre\u00e7os muito abaixo dos valores de mercado.<\/p>\n\n\n\n<p>Segundo a Receita Federal, o <a href=\"https:\/\/receita.economia.gov.br\/sobre\/acoes-e-programas\/mercadorias-apreendidas\/leilao\/leilao-eletronico\/copy_of_leilao-eletronico\">Sistema de Leil\u00e3o Eletr\u00f4nico<\/a> \u00e9 o meio pelo qual a Secretaria da Receita Federal do Brasil (RFB) realiza leil\u00f5es eletr\u00f4nicos de <strong>mercadorias apreendidas ou abandonadas<\/strong>.<\/p>\n\n\n\n<p>Como se sabe, o fisco federal \u00e9 o respons\u00e1vel pelo controle da aduana, principal porta de entrada de produtos frutos de contrabando ou descaminho.<\/p>\n\n\n\n<p>Uma vez que estes produtos s\u00e3o apreendidos pela Receita, o importador ou transportador tem 2 sa\u00eddas: pagar os impostos devidos pela importa\u00e7\u00e3o, juntamente com a multa pelo crime praticado, ou simplesmente abandonar a mercadoria.<\/p>\n\n\n\n<p>Tendo em vista que os impostos incidentes na importa\u00e7\u00e3o e as san\u00e7\u00f5es aplicadas pelos crimes de contrabando e descaminho s\u00e3o bastante elevados, muitos importadores optam por simplesmente deixar suas mercadorias, muitas delas ainda lacradas, para que a Receita d\u00ea a elas outros fins.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-mercadorias-apreendidas-pela-receita-federal\">Mercadorias Apreendidas pela Receita Federal<\/h2>\n\n\n\n<p>Conforme previsto no artigo 29, item II, do <a href=\"http:\/\/www.planalto.gov.br\/ccivil_03\/decreto-lei\/del1455.htm\">Decreto-lei n\u00ba 1455\/76<\/a>, atualmente regulamentado pelo <a href=\"http:\/\/www.planalto.gov.br\/ccivil_03\/_ato2007-2010\/2009\/decreto\/d6759.htm\">Decreto n\u00ba 6.759\/09<\/a>, e pela <a href=\"http:\/\/normas.receita.fazenda.gov.br\/sijut2consulta\/link.action?visao=anotado&amp;idAto=26101\">Portaria MF 282\/11<\/a>, a destina\u00e7\u00e3o de mercadorias apreendidas, pode ocorrer nas seguintes&nbsp; modalidades:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Leil\u00e3o;<\/li>\n\n\n\n<li>Destrui\u00e7\u00e3o; e<\/li>\n\n\n\n<li>Doa\u00e7\u00e3o\/Incorpora\u00e7\u00e3o aos \u00f3rg\u00e3os da administra\u00e7\u00e3o p\u00fablica direta e indireta.<\/li>\n<\/ul>\n\n\n\n<p>A destrui\u00e7\u00e3o se aplica a:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>cigarros e demais derivados do tabaco;<\/li>\n\n\n\n<li>mercadorias deterioradas, danificadas, estragadas, com data de validade vencida, que n\u00e3o atendam exig\u00eancias sanit\u00e1rias ou agropecu\u00e1rias, ou que estejam em desacordo com regulamentos ou normas t\u00e9cnicas, e outras, as quais, de qualquer modo, forem imprest\u00e1veis para fins de aliena\u00e7\u00e3o ou incorpora\u00e7\u00e3o;<\/li>\n\n\n\n<li>fonogramas, livros e obras audiovisuais com ind\u00edcios de viola\u00e7\u00e3o ao direito autoral;<\/li>\n\n\n\n<li>mercadorias apreendidas em decorr\u00eancia de inobserv\u00e2ncia \u00e0 Lei de Propriedade Industrial; ou produtos assinalados com marca falsificada, alterada ou imitada;<\/li>\n<\/ul>\n\n\n\n<p>Poder\u00e3o ainda ser objeto de destrui\u00e7\u00e3o, quando assim recomendar o interesse da Administra\u00e7\u00e3o ou da economia do Pa\u00eds, a crit\u00e9rio da autoridade competente:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>mercadorias colocadas em leil\u00e3o por <strong>duas vezes e n\u00e3o alienadas<\/strong>;<\/li>\n\n\n\n<li>mercadorias de baixo valor, assim consideradas aquelas cujo valor unit\u00e1rio seja <strong>inferior a R$ 50,00<\/strong>.<\/li>\n<\/ul>\n\n\n\n<p>Como vimos, o leil\u00e3o \u00e9 a regra, e a destrui\u00e7\u00e3o a exce\u00e7\u00e3o. Ademais, a incorpora\u00e7\u00e3o depender\u00e1 de formaliza\u00e7\u00e3o do pedido por parte do \u00f3rg\u00e3o interessado ou de determina\u00e7\u00e3o de autoridade competente.<\/p>\n\n\n\n<p>Desse modo, vamos entender melhor como funciona e como participar do leil\u00e3o da receita federal.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-leilao-da-receita-federal\">Leil\u00e3o da Receita Federal<\/h2>\n\n\n\n<p>A PORTARIA MF N\u00ba 282 disp\u00f5e que a aliena\u00e7\u00e3o mediante licita\u00e7\u00e3o, na modalidade leil\u00e3o, ser\u00e1 realizada preferencialmente por meio eletr\u00f4nico.<\/p>\n\n\n\n<p>Os produtos que fazem parte dos leil\u00f5es s\u00e3o de todos os tipos, desde porcelanatos, passando por eletr\u00f4nicos de uso pessoal, at\u00e9 mesmo carros e pe\u00e7as para aeronaves e embarca\u00e7\u00f5es. Al\u00e9m disso, muitos destes produtos s\u00e3o totalmente novos, embalados e lacrados, podendo ser comprados a pre\u00e7os inferiores \u00e0 metade do valor de mercado. E com a grande vantagem de poder comprar essas mercadorias sem sair de casa, de maneira totalmente digital.<\/p>\n\n\n\n<p>Todavia, ser\u00e1 necess\u00e1rio providenciar um <strong>Certificado Digital<\/strong> para isso. Veja: \u201cOs interessados em participar do Leil\u00e3o Eletr\u00f4nico dever\u00e3o acessar o s\u00edtio da RFB, Portal (<a href=\"https:\/\/cav.receita.fazenda.gov.br\/autenticacao\/login\/index\">e-CAC<\/a>), mediante a utiliza\u00e7\u00e3o de <strong>Certificado Digital v\u00e1lido<\/strong>, e escolher a op\u00e7\u00e3o de servi\u00e7o \u2018<strong>Sistema de Leil\u00e3o Eletr\u00f4nico\u2019<\/strong>&#8220;.<\/p>\n\n\n\n<p>Veja este <a href=\"http:\/\/receita.economia.gov.br\/interface\/atendimento-virtual\/arquivos-e-imagens\/passo-a-passocodigodeacesso.pdf\">passo a passo<\/a> de como gerar seu primeiro c\u00f3digo de acesso no Portal e-CAC.<\/p>\n\n\n\n<p>A princ\u00edpio, qualquer cidad\u00e3o brasileiro ou pessoa jur\u00eddica pode participar desses leil\u00f5es. Todavia, alguns leil\u00f5es s\u00e3o exclusivos para pessoas jur\u00eddicas.<\/p>\n\n\n\n<p>Clique neste <em><a href=\"http:\/\/www25.receita.fazenda.gov.br\/sle-sociedade\/portal\">link<\/a><\/em> e veja quais os produtos est\u00e3o dispon\u00edveis. Basta realizar um filtro no canto esquerdo da tela, e selecionar o tipo de lote que deseja procurar.<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"567\" height=\"264\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/06\/01102009\/image-2.png\" alt=\" leil\u00e3o da receita federal\" class=\"wp-image-520984\" srcset=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/06\/01102009\/image-2.png 567w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/06\/01102009\/image-2-300x140.png 300w\" sizes=\"auto, (max-width: 567px) 100vw, 567px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-lotes-de-produtos\">Lotes de Produtos<\/h2>\n\n\n\n<p>Uma vez que a quantidade de produtos apreendidos \u00e9 elevada, os produtos s\u00e3o normalmente vendidos em lotes fechados, e n\u00e3o em unidades separadamente. Dessa forma, os participantes fazem lances nos lotes e, caso saiam vencedores, precisam levar todos os produtos que fazem parte daquele pacote.<\/p>\n\n\n\n<p>Veja esse lote com 10 produtos, com lance inicial de <strong>R$ 3.000,00:<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-table is-style-stripes\"><table><tbody><tr><td class=\"has-text-align-center\" data-align=\"center\"><strong>Produto<\/strong><\/td><td class=\"has-text-align-center\" data-align=\"center\"><strong>Quantidade<\/strong><\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\"><strong>iPhone XS MAX 64GB<\/strong><\/td><td class=\"has-text-align-center\" data-align=\"center\">1<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\"><strong>iPhone 7 PLUS 128GB<\/strong><\/td><td class=\"has-text-align-center\" data-align=\"center\">1<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\"><strong>SAMSUNG S9 64 GB<\/strong><\/td><td class=\"has-text-align-center\" data-align=\"center\">2<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\"><strong>CAPAS DE CELULAR SAMSUNG S9<\/strong><\/td><td class=\"has-text-align-center\" data-align=\"center\">2<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\"><strong>SMARTPHONE APPLE C\/ ACESSORIOS<\/strong><\/td><td class=\"has-text-align-center\" data-align=\"center\">1<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\"><strong>Celular MEIZU PRO 7<\/strong><\/td><td class=\"has-text-align-center\" data-align=\"center\">1<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\"><strong>SAMSUNG GALAXY S9 usado<\/strong><\/td><td class=\"has-text-align-center\" data-align=\"center\">1<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\"><strong>Celular J9<\/strong><\/td><td class=\"has-text-align-center\" data-align=\"center\">1<\/td><\/tr><\/tbody><\/table><figcaption class=\"wp-element-caption\">Lote de Produtos- Leil\u00e3o da Receita Federal<\/figcaption><\/figure>\n\n\n\n<p>Inacredit\u00e1vel, n\u00e3o \u00e9 mesmo? Todos esses produtos, de valores extremamente elevados, com lance inicial de apenas R$ 3.000,00.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-como-pagar-e-onde-retirar-as-mercadorias\">Como pagar e onde retirar as mercadorias?<\/h2>\n\n\n\n<p>O pagamento ser\u00e1 realizado por meio da emiss\u00e3o de um Documento de Arrecada\u00e7\u00e3o de Receitas Federais (DARF). Al\u00e9m disso, ainda \u00e9 poss\u00edvel escolher entre fazer o pagamento total no primeiro dia \u00fatil ap\u00f3s o leil\u00e3o, ou ent\u00e3o pagar apenas 20% no primeiro dia \u00fatil e os 80% restantes em at\u00e9 oito dias corridos.<\/p>\n\n\n\n<p>O grande percal\u00e7o \u00e9, todavia, para retirar as mercadorias, uma vez que a Receita Federal n\u00e3o ir\u00e1 lhe enviar os produtos por Correios. As informa\u00e7\u00f5es sobre a retirada est\u00e3o presentes nos editais de cada leil\u00e3o.<\/p>\n\n\n\n<p>Sendo assim, a responsabilidade pela retirada \u00e9 do comprador, o que normalmente envolve comparecer aos locais f\u00edsicos onde se encontram as mercadorias.<\/p>\n\n\n\n<p>Cumpre salientar que os produtos vendidos pelo leil\u00e3o est\u00e3o, ainda, sujeitos \u00e0 incid\u00eancia do ICMS (imposto estadual), que para algumas mercadorias chega \u00e0 casa dos 20%.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-destinacao-do-valor-arrecadado\">Destina\u00e7\u00e3o do Valor Arrecadado<\/h2>\n\n\n\n<p>O produto da aliena\u00e7\u00e3o por leil\u00e3o ter\u00e1 a seguinte destina\u00e7\u00e3o:<\/p>\n\n\n\n<ol class=\"wp-block-list\" type=\"1\">\n<li><strong>60%<\/strong>, ao Fundo Especial de Desenvolvimento e Aperfei\u00e7oamento das Atividades de Fiscaliza\u00e7\u00e3o \u2013 FUNDAF; e<\/li>\n\n\n\n<li><strong>40%<\/strong> \u00e0 seguridade social.<\/li>\n<\/ol>\n\n\n\n<p>Ademais, n\u00e3o haver\u00e1 incid\u00eancia de <strong>tributos federais<\/strong> sobre o valor da aliena\u00e7\u00e3o, mediante licita\u00e7\u00e3o, das mercadorias de que trata este artigo. Contudo, os produtos n\u00e3o est\u00e3o isentos de tributos estaduais.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-finalizando\">Finalizando<\/h2>\n\n\n\n<p>E a\u00ed, gostou da ideia de poder comprar um iPhone por um pre\u00e7o banal?<\/p>\n\n\n\n<p>Certamente que quem se interessar, ser\u00e1 preciso enfrentar certas burocracias iniciais, como a cria\u00e7\u00e3o de um Certificado Digital, por exemplo. Outras desvantagens s\u00e3o em rela\u00e7\u00e3o ao pagamento (\u00e0 vista) e a necessidade de retirar o produto no local.<\/p>\n\n\n\n<p>Contudo, o baix\u00edssimo valor sobrep\u00f5e essas desvantagens, sem dizer que estaremos contribuindo para a <strong>seguridade social: sa\u00fade, assist\u00eancia social e previd\u00eancia social<\/strong>.<\/p>\n\n\n\n<p>Vai participar do pr\u00f3ximo leil\u00e3o? Deixa seu coment\u00e1rio abaixo.<\/p>\n\n\n\n<p>Um forte abra\u00e7o<\/p>\n\n\n\n<p>Leandro Ricardo M. Silveira<\/p>\n\n\n\n<p><strong>Instagram: <\/strong><a href=\"https:\/\/www.instagram.com\/leandro.rms12\/\">https:\/\/www.instagram.com\/leandro.rms12\/<\/a><\/p>\n\n\n\n<p class=\"has-text-align-center has-very-light-gray-color has-vivid-purple-background-color has-text-color has-background\" style=\"font-size:clamp(14px, 0.875rem + ((1vw - 3.2px) * 0.392), 18px);px\"><strong>SISTEMA DE QUEST\u00d5ES &#8211; <a href=\"https:\/\/questoes.estrategiaconcursos.com.br\/\">Experimente Gr\u00e1tis por 7 dias<\/a><\/strong><\/p>\n\n\n\n<p><em><strong>Assinatura Anual Ilimitada*<\/strong><\/em><\/p>\n\n\n\n<p class=\"has-text-align-center\"><em>Prepare-se com o melhor material e com quem mais aprova em Concursos P\u00fablicos em todo o pa\u00eds. Assine agora a nossa Assinatura Anual e tenha acesso ilimitado* a todos os nossos cursos.<\/em><\/p>\n\n\n\n<p class=\"has-text-align-center has-luminous-vivid-amber-background-color has-background\" style=\"font-size:clamp(14.642px, 0.915rem + ((1vw - 3.2px) * 0.721), 22px);px\"><strong>ASSINE AGORA<\/strong>&nbsp;\u2013&nbsp;<a rel=\"noreferrer noopener\" href=\"https:\/\/www.estrategiaconcursos.com.br\/assinaturas\" target=\"_blank\"><strong>Assinatura Ilimitada<\/strong><\/a><\/p>\n\n\n\n<p class=\"has-text-align-center has-medium-font-size\"><em><strong>Fique por dentro de todos os concursos<\/strong><\/em>:<\/p>\n\n\n\n<p class=\"has-text-align-center has-pale-cyan-blue-background-color has-background\" style=\"font-size:clamp(14.642px, 0.915rem + ((1vw - 3.2px) * 0.721), 22px);px\"><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-abertos\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Concursos abertos<\/strong><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>J\u00e1 pensou em comprar eletr\u00f4nicos e at\u00e9 mesmo carros por menos da metade do pre\u00e7o? E o melhor: de maneira totalmente legal. Ent\u00e3o saiba mais sobre como funciona o leil\u00e3o da receita federal. Ol\u00e1, estrategista. Tudo joia? Ficou interessado, n\u00e3o \u00e9? Ali\u00e1s, quem n\u00e3o gostaria de comprar produtos de alta qualidade, com alto valor agregado, [&hellip;]<\/p>\n","protected":false},"author":1668,"featured_media":520982,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"post_tipo":"article","footnotes":""},"categories":[1],"tags":[192481,484],"tax_estado":[],"class_list":["post-520977","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cursos-e-concursos","tag-leilao","tag-receita-federal"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.2 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Saiba como participar do leil\u00e3o da Receita Federal.<\/title>\n<meta name=\"description\" content=\"Saiba como comprar eletr\u00f4nicos e at\u00e9 mesmo ve\u00edculos por menos da metade do pre\u00e7o. O leil\u00e3o da receita federal \u00e9 uma \u00f3tima op\u00e7\u00e3o para economizar.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/saiba-como-participar-do-leilao-da-receita-federal\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Saiba como participar do leil\u00e3o da Receita Federal.\" \/>\n<meta property=\"og:description\" content=\"Saiba como comprar eletr\u00f4nicos e at\u00e9 mesmo ve\u00edculos por menos da metade do pre\u00e7o. O leil\u00e3o da receita federal \u00e9 uma \u00f3tima op\u00e7\u00e3o para economizar.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/saiba-como-participar-do-leilao-da-receita-federal\/\" \/>\n<meta property=\"og:site_name\" content=\"Estrat\u00e9gia Concursos\" \/>\n<meta property=\"article:published_time\" content=\"2020-06-18T15:30:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-07-06T18:16:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/06\/01101945\/14142001844193.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1120\" \/>\n\t<meta property=\"og:image:height\" content=\"420\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Leandro Ricardo Machado da Silveira\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:site\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Leandro Ricardo Machado da Silveira\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/saiba-como-participar-do-leilao-da-receita-federal\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/saiba-como-participar-do-leilao-da-receita-federal\/\"},\"author\":{\"name\":\"Leandro Ricardo Machado da Silveira\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/c666a44fbce7e2e70009a9c13549267a\"},\"headline\":\"Saiba como participar do leil\u00e3o da Receita Federal.\",\"datePublished\":\"2020-06-18T15:30:00+00:00\",\"dateModified\":\"2023-07-06T18:16:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/saiba-como-participar-do-leilao-da-receita-federal\/\"},\"wordCount\":1272,\"commentCount\":10,\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/saiba-como-participar-do-leilao-da-receita-federal\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/06\/01101945\/14142001844193.jpg\",\"keywords\":[\"leil\u00e3o\",\"Receita Federal\"],\"articleSection\":[\"Concursos P\u00fablicos\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/saiba-como-participar-do-leilao-da-receita-federal\/#respond\"]}],\"copyrightYear\":\"2020\",\"copyrightHolder\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/saiba-como-participar-do-leilao-da-receita-federal\/\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/saiba-como-participar-do-leilao-da-receita-federal\/\",\"name\":\"Saiba como participar do leil\u00e3o da Receita Federal.\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/saiba-como-participar-do-leilao-da-receita-federal\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/saiba-como-participar-do-leilao-da-receita-federal\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/06\/01101945\/14142001844193.jpg\",\"datePublished\":\"2020-06-18T15:30:00+00:00\",\"dateModified\":\"2023-07-06T18:16:44+00:00\",\"description\":\"Saiba como comprar eletr\u00f4nicos e at\u00e9 mesmo ve\u00edculos por menos da metade do pre\u00e7o. O leil\u00e3o da receita federal \u00e9 uma \u00f3tima op\u00e7\u00e3o para economizar.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/saiba-como-participar-do-leilao-da-receita-federal\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/saiba-como-participar-do-leilao-da-receita-federal\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/saiba-como-participar-do-leilao-da-receita-federal\/#primaryimage\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/06\/01101945\/14142001844193.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/06\/01101945\/14142001844193.jpg\",\"width\":1120,\"height\":420},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/saiba-como-participar-do-leilao-da-receita-federal\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Saiba como participar do leil\u00e3o da Receita Federal.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"name\":\"Estrat\u00e9gia Concursos\",\"description\":\"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.\",\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\",\"name\":\"Estrat\u00e9gia Concursos\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"width\":230,\"height\":60,\"caption\":\"Estrat\u00e9gia Concursos\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/EstratConcursos\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/c666a44fbce7e2e70009a9c13549267a\",\"name\":\"Leandro Ricardo Machado da Silveira\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/6fb25994d16b9649838400aa459b16c1c83f558e0fd6ebebd16da0473908b291?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/6fb25994d16b9649838400aa459b16c1c83f558e0fd6ebebd16da0473908b291?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/6fb25994d16b9649838400aa459b16c1c83f558e0fd6ebebd16da0473908b291?s=96&d=mm&r=g\",\"caption\":\"Leandro Ricardo Machado da Silveira\"},\"description\":\"Engenheiro Aeron\u00e1utico, formado pela Universidade Federal de Uberl\u00e2ndia, possui MBA em Administra\u00e7\u00e3o e Finan\u00e7as Corporativas e aprovado nos concursos de Auditor Fiscal SEFAZ-SC e SEFAZ-GO.\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/leandro_vzthotmail-com\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Saiba como participar do leil\u00e3o da Receita Federal.","description":"Saiba como comprar eletr\u00f4nicos e at\u00e9 mesmo ve\u00edculos por menos da metade do pre\u00e7o. O leil\u00e3o da receita federal \u00e9 uma \u00f3tima op\u00e7\u00e3o para economizar.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.estrategiaconcursos.com.br\/blog\/saiba-como-participar-do-leilao-da-receita-federal\/","og_locale":"pt_BR","og_type":"article","og_title":"Saiba como participar do leil\u00e3o da Receita Federal.","og_description":"Saiba como comprar eletr\u00f4nicos e at\u00e9 mesmo ve\u00edculos por menos da metade do pre\u00e7o. O leil\u00e3o da receita federal \u00e9 uma \u00f3tima op\u00e7\u00e3o para economizar.","og_url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/saiba-como-participar-do-leilao-da-receita-federal\/","og_site_name":"Estrat\u00e9gia Concursos","article_published_time":"2020-06-18T15:30:00+00:00","article_modified_time":"2023-07-06T18:16:44+00:00","og_image":[{"width":1120,"height":420,"url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/06\/01101945\/14142001844193.jpg","type":"image\/jpeg"}],"author":"Leandro Ricardo Machado da Silveira","twitter_card":"summary_large_image","twitter_creator":"@EstratConcursos","twitter_site":"@EstratConcursos","twitter_misc":{"Escrito por":"Leandro Ricardo Machado da Silveira","Est. tempo de leitura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/saiba-como-participar-do-leilao-da-receita-federal\/#article","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/saiba-como-participar-do-leilao-da-receita-federal\/"},"author":{"name":"Leandro Ricardo Machado da Silveira","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/c666a44fbce7e2e70009a9c13549267a"},"headline":"Saiba como participar do leil\u00e3o da Receita Federal.","datePublished":"2020-06-18T15:30:00+00:00","dateModified":"2023-07-06T18:16:44+00:00","mainEntityOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/saiba-como-participar-do-leilao-da-receita-federal\/"},"wordCount":1272,"commentCount":10,"publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/saiba-como-participar-do-leilao-da-receita-federal\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/06\/01101945\/14142001844193.jpg","keywords":["leil\u00e3o","Receita Federal"],"articleSection":["Concursos P\u00fablicos"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/saiba-como-participar-do-leilao-da-receita-federal\/#respond"]}],"copyrightYear":"2020","copyrightHolder":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/saiba-como-participar-do-leilao-da-receita-federal\/","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/saiba-como-participar-do-leilao-da-receita-federal\/","name":"Saiba como participar do leil\u00e3o da Receita Federal.","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/saiba-como-participar-do-leilao-da-receita-federal\/#primaryimage"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/saiba-como-participar-do-leilao-da-receita-federal\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/06\/01101945\/14142001844193.jpg","datePublished":"2020-06-18T15:30:00+00:00","dateModified":"2023-07-06T18:16:44+00:00","description":"Saiba como comprar eletr\u00f4nicos e at\u00e9 mesmo ve\u00edculos por menos da metade do pre\u00e7o. O leil\u00e3o da receita federal \u00e9 uma \u00f3tima op\u00e7\u00e3o para economizar.","breadcrumb":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/saiba-como-participar-do-leilao-da-receita-federal\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/saiba-como-participar-do-leilao-da-receita-federal\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/saiba-como-participar-do-leilao-da-receita-federal\/#primaryimage","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/06\/01101945\/14142001844193.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/06\/01101945\/14142001844193.jpg","width":1120,"height":420},{"@type":"BreadcrumbList","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/saiba-como-participar-do-leilao-da-receita-federal\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.estrategiaconcursos.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Saiba como participar do leil\u00e3o da Receita Federal."}]},{"@type":"WebSite","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","name":"Estrat\u00e9gia Concursos","description":"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.","publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization","name":"Estrat\u00e9gia Concursos","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","width":230,"height":60,"caption":"Estrat\u00e9gia Concursos"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/EstratConcursos"]},{"@type":"Person","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/c666a44fbce7e2e70009a9c13549267a","name":"Leandro Ricardo Machado da Silveira","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/6fb25994d16b9649838400aa459b16c1c83f558e0fd6ebebd16da0473908b291?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/6fb25994d16b9649838400aa459b16c1c83f558e0fd6ebebd16da0473908b291?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6fb25994d16b9649838400aa459b16c1c83f558e0fd6ebebd16da0473908b291?s=96&d=mm&r=g","caption":"Leandro Ricardo Machado da Silveira"},"description":"Engenheiro Aeron\u00e1utico, formado pela Universidade Federal de Uberl\u00e2ndia, possui MBA em Administra\u00e7\u00e3o e Finan\u00e7as Corporativas e aprovado nos concursos de Auditor Fiscal SEFAZ-SC e SEFAZ-GO.","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/leandro_vzthotmail-com\/"}]}},"_links":{"self":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/520977","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/users\/1668"}],"replies":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/comments?post=520977"}],"version-history":[{"count":8,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/520977\/revisions"}],"predecessor-version":[{"id":1244578,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/520977\/revisions\/1244578"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media\/520982"}],"wp:attachment":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media?parent=520977"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/categories?post=520977"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tags?post=520977"},{"taxonomy":"tax_estado","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tax_estado?post=520977"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}