{"id":520061,"date":"2023-01-26T08:47:00","date_gmt":"2023-01-26T11:47:00","guid":{"rendered":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?p=520061"},"modified":"2023-01-26T08:47:56","modified_gmt":"2023-01-26T11:47:56","slug":"guia-de-estudos-tcm-sp","status":"publish","type":"post","link":"https:\/\/www.estrategiaconcursos.com.br\/blog\/guia-de-estudos-tcm-sp\/","title":{"rendered":"Guia de Estudos para o concurso TCM SP 2023"},"content":{"rendered":"\n<div class=\"wp-block-group is-layout-flow wp-block-group-is-layout-flow\">\n<div class=\"wp-block-group is-layout-flow wp-block-group-is-layout-flow\">\n<p class=\"has-text-align-right\"><em>Cadernos de Quest\u00f5es elaborados, por Mat\u00e9ria,<\/em><br \/><em>conforme o Edital do Concurso TCM SP.<\/em><\/p>\n\n\n\n<p>Acesse, neste artigo, os <em>Cadernos de Quest\u00f5es<\/em> elaborados, para cada <em>Mat\u00e9ria<\/em>, conforme o <em>conte\u00fado program\u00e1tico<\/em> do Edital TCM SP 2023.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-cadernos-de-questoes-tcm-sp\"><mark style=\"background-color:rgba(0, 0, 0, 0);color:#5823f7\" class=\"has-inline-color\">Cadernos de Quest\u00f5es TCM SP<\/mark><\/h2>\n\n\n\n<p><strong>Auxiliar T\u00e9cnico de Controle Externo &#8211; Suporte Administrativo<\/strong><\/p>\n\n\n\n<p><a href=\"https:\/\/concursos.estrategia.com\/cadernos-e-simulados\/cadernos\/808c1c33-1511-4535-b228-3af2751ad2ca\" target=\"_blank\" rel=\"noreferrer noopener\">L\u00edngua Portuguesa<br \/><\/a><a href=\"https:\/\/concursos.estrategia.com\/cadernos-e-simulados\/cadernos\/4f17343c-8fe4-4756-be84-714d6365dd3d\" target=\"_blank\" rel=\"noreferrer noopener\">Racioc\u00ednio L\u00f3gico<br \/><\/a><a href=\"https:\/\/concursos.estrategia.com\/cadernos-e-simulados\/cadernos\/2b55b889-6038-4a2f-b139-4431ca69703e\" target=\"_blank\" rel=\"noreferrer noopener\">Estatuto dos Servidores P\u00fablicos do Munic\u00edpio de SP<br \/><\/a><a href=\"https:\/\/concursos.estrategia.com\/cadernos-e-simulados\/cadernos\/ce955cd3-4f17-4aa4-a2c6-07195023dbd2\" target=\"_blank\" rel=\"noreferrer noopener\">Atendimento + Rela\u00e7\u00f5es Interpessoais + Trabalho em Equipe<br \/><\/a><a href=\"https:\/\/concursos.estrategia.com\/cadernos-e-simulados\/cadernos\/22fd5258-605d-4376-a671-dd8b928f67cb\" target=\"_blank\" rel=\"noreferrer noopener\">No\u00e7\u00f5es de Arquivos<br \/><\/a><a href=\"https:\/\/concursos.estrategia.com\/cadernos-e-simulados\/cadernos\/127a119b-053f-49d0-a00c-895a3205e479\" target=\"_blank\" rel=\"noreferrer noopener\">No\u00e7\u00f5es de Direito Constitucional<br \/><\/a><a href=\"https:\/\/concursos.estrategia.com\/cadernos-e-simulados\/cadernos\/17e13707-0c35-4332-aa9f-33b5616b9e36\" target=\"_blank\" rel=\"noreferrer noopener\">No\u00e7\u00f5es de Direito Administrativo<br \/><\/a><a href=\"https:\/\/concursos.estrategia.com\/cadernos-e-simulados\/cadernos\/f537c464-5d47-4315-997d-4ae9e6f40bfa\" target=\"_blank\" rel=\"noreferrer noopener\">Auditoria<\/a><br \/><a href=\"https:\/\/concursos.estrategia.com\/cadernos-e-simulados\/cadernos\/62c8fb05-a49a-4942-af7d-a3eb26d163c7\" target=\"_blank\" rel=\"noreferrer noopener\">No\u00e7\u00f5es de Contabilidade Geral<br \/><\/a><a href=\"https:\/\/concursos.estrategia.com\/cadernos-e-simulados\/cadernos\/1c2f8c2f-c3cf-4b78-ab3c-fff648599bb5\" target=\"_blank\" rel=\"noreferrer noopener\">No\u00e7\u00f5es de Or\u00e7amento P\u00fablico<br \/><\/a><a href=\"https:\/\/concursos.estrategia.com\/cadernos-e-simulados\/cadernos\/928b480f-330b-4813-a2af-070432fa4a00\" target=\"_blank\" rel=\"noreferrer noopener\">No\u00e7\u00f5es de Contabilidade P\u00fablica<br \/><\/a><a href=\"https:\/\/concursos.estrategia.com\/cadernos-e-simulados\/cadernos\/3e05dc61-6be1-4476-8c1a-83feff747a05\" target=\"_blank\" rel=\"noreferrer noopener\">No\u00e7\u00f5es de Controle Externo na Administra\u00e7\u00e3o P\u00fablica<br \/><\/a><a href=\"https:\/\/concursos.estrategia.com\/cadernos-e-simulados\/cadernos\/9b43d3db-61b8-4f80-8b8e-0d0c71bca78a\" target=\"_blank\" rel=\"noreferrer noopener\">Correspond\u00eancia Oficial<br \/><\/a><a href=\"https:\/\/concursos.estrategia.com\/cadernos-e-simulados\/cadernos\/d835586c-fda8-4aac-9611-462fe934bd19\" target=\"_blank\" rel=\"noreferrer noopener\">Lei de Prote\u00e7\u00e3o de Dados Pessoais<\/a><\/p>\n\n\n\n<p><strong>Auxiliar T\u00e9cnico de Fiscaliza\u00e7\u00e3o &#8211; Tecnologia da Informa\u00e7\u00e3o<\/strong><\/p>\n\n\n\n<p><a href=\"https:\/\/concursos.estrategia.com\/cadernos-e-simulados\/cadernos\/808c1c33-1511-4535-b228-3af2751ad2ca\" target=\"_blank\" rel=\"noreferrer noopener\">L\u00edngua Portuguesa<br \/><\/a><a href=\"https:\/\/concursos.estrategia.com\/cadernos-e-simulados\/cadernos\/4f17343c-8fe4-4756-be84-714d6365dd3d\" target=\"_blank\" rel=\"noreferrer noopener\">Racioc\u00ednio L\u00f3gico<br \/><\/a><a href=\"https:\/\/concursos.estrategia.com\/cadernos-e-simulados\/cadernos\/2b55b889-6038-4a2f-b139-4431ca69703e\" target=\"_blank\" rel=\"noreferrer noopener\">Estatuto dos Servidores P\u00fablicos do Munic\u00edpio de SP<br \/><\/a><a href=\"https:\/\/concursos.estrategia.com\/cadernos-e-simulados\/cadernos\/ce955cd3-4f17-4aa4-a2c6-07195023dbd2\" target=\"_blank\" rel=\"noreferrer noopener\">Atendimento + Rela\u00e7\u00f5es Interpessoais + Trabalho em Equipe<br \/><\/a><a href=\"https:\/\/concursos.estrategia.com\/cadernos-e-simulados\/cadernos\/22fd5258-605d-4376-a671-dd8b928f67cb\" target=\"_blank\" rel=\"noreferrer noopener\">No\u00e7\u00f5es de Arquivos<br \/><\/a><a href=\"https:\/\/concursos.estrategia.com\/cadernos-e-simulados\/cadernos\/127a119b-053f-49d0-a00c-895a3205e479\" target=\"_blank\" rel=\"noreferrer noopener\">No\u00e7\u00f5es de Direito Constitucional<br \/><\/a><a href=\"https:\/\/concursos.estrategia.com\/cadernos-e-simulados\/cadernos\/17e13707-0c35-4332-aa9f-33b5616b9e36\" target=\"_blank\" rel=\"noreferrer noopener\">No\u00e7\u00f5es de Direito Administrativo<br \/><\/a><a href=\"https:\/\/concursos.estrategia.com\/cadernos-e-simulados\/cadernos\/f537c464-5d47-4315-997d-4ae9e6f40bfa\" target=\"_blank\" rel=\"noreferrer noopener\">Auditoria<\/a><br \/><a href=\"https:\/\/concursos.estrategia.com\/cadernos-e-simulados\/cadernos\/62c8fb05-a49a-4942-af7d-a3eb26d163c7\" target=\"_blank\" rel=\"noreferrer noopener\">No\u00e7\u00f5es de Contabilidade Geral<br \/><\/a><a href=\"https:\/\/concursos.estrategia.com\/cadernos-e-simulados\/cadernos\/1c2f8c2f-c3cf-4b78-ab3c-fff648599bb5\" target=\"_blank\" rel=\"noreferrer noopener\">No\u00e7\u00f5es de Or\u00e7amento P\u00fablico<br \/><\/a><a href=\"https:\/\/concursos.estrategia.com\/cadernos-e-simulados\/cadernos\/928b480f-330b-4813-a2af-070432fa4a00\" target=\"_blank\" rel=\"noreferrer noopener\">No\u00e7\u00f5es de Contabilidade P\u00fablica<br \/><\/a><a href=\"https:\/\/concursos.estrategia.com\/cadernos-e-simulados\/cadernos\/3e05dc61-6be1-4476-8c1a-83feff747a05\" target=\"_blank\" rel=\"noreferrer noopener\">No\u00e7\u00f5es de Controle Externo na Administra\u00e7\u00e3o P\u00fablica<\/a><br \/><a href=\"https:\/\/concursos.estrategia.com\/cadernos-e-simulados\/cadernos\/4934fccd-933c-4896-a505-69fe3e526abc\" target=\"_blank\" rel=\"noreferrer noopener\">Desenvolvimento de Software<br \/><\/a><a href=\"https:\/\/concursos.estrategia.com\/cadernos-e-simulados\/cadernos\/e597c1f7-400c-4295-903f-ac77958c1fe1\" target=\"_blank\" rel=\"noreferrer noopener\">Engenharia de Software<br \/><\/a><a href=\"https:\/\/concursos.estrategia.com\/cadernos-e-simulados\/cadernos\/b5c3a750-c6a6-4e04-897d-81a2f5ccf191\" target=\"_blank\" rel=\"noreferrer noopener\">Banco de Dados<br \/><\/a><a href=\"https:\/\/concursos.estrategia.com\/cadernos-e-simulados\/cadernos\/9b43d3db-61b8-4f80-8b8e-0d0c71bca78a\" target=\"_blank\" rel=\"noreferrer noopener\">Correspond\u00eancia Oficial<br \/><\/a><a href=\"https:\/\/concursos.estrategia.com\/cadernos-e-simulados\/cadernos\/d835586c-fda8-4aac-9611-462fe934bd19\" target=\"_blank\" rel=\"noreferrer noopener\">Lei de Prote\u00e7\u00e3o de Dados Pessoais<\/a><\/p>\n\n\n\n<p><strong>Auditor de Controle Externo &#8211; Tecnologia da Informa\u00e7\u00e3o<\/strong><\/p>\n\n\n\n<p><a href=\"https:\/\/concursos.estrategia.com\/cadernos-e-simulados\/cadernos\/20c9cac3-42ed-406a-a3f9-9ad3dd0ed9e5\" target=\"_blank\" rel=\"noreferrer noopener\">L\u00edngua Portuguesa<br \/><\/a><a href=\"https:\/\/concursos.estrategia.com\/cadernos-e-simulados\/cadernos\/0820493c-b820-46f5-95f4-43d58fe604e6\" target=\"_blank\" rel=\"noreferrer noopener\">Administra\u00e7\u00e3o<\/a><br \/><a href=\"https:\/\/concursos.estrategia.com\/cadernos-e-simulados\/cadernos\/abdae964-3f60-4a37-9ff7-e448764e55cf\" target=\"_blank\" rel=\"noreferrer noopener\">Auditoria<\/a><br \/><a href=\"https:\/\/concursos.estrategia.com\/cadernos-e-simulados\/cadernos\/c52db97b-b88f-417f-b597-16eb63be6547\" target=\"_blank\" rel=\"noreferrer noopener\">Contabilidade Geral<br \/><\/a><a href=\"https:\/\/concursos.estrategia.com\/cadernos-e-simulados\/cadernos\/13629d5d-f785-4172-a3d1-0d287915f462\" target=\"_blank\" rel=\"noreferrer noopener\">Or\u00e7amento P\u00fablico<br \/><\/a><a href=\"https:\/\/concursos.estrategia.com\/cadernos-e-simulados\/cadernos\/c6754946-0cd6-4ef6-a911-bd10f2467811\" target=\"_blank\" rel=\"noreferrer noopener\">Contabilidade P\u00fablica<br \/><\/a><a href=\"https:\/\/concursos.estrategia.com\/cadernos-e-simulados\/cadernos\/7eda5249-c4c6-44e0-b83e-72ae2c059899\" target=\"_blank\" rel=\"noreferrer noopener\">Controle Externo na Gest\u00e3o P\u00fablica<br \/><\/a><a href=\"https:\/\/concursos.estrategia.com\/cadernos-e-simulados\/cadernos\/0d71a46c-4123-49e3-b871-c33b487da3a4\" target=\"_blank\" rel=\"noreferrer noopener\">Direito Constitucional e Lei Org\u00e2nica<br \/><\/a><a href=\"https:\/\/concursos.estrategia.com\/cadernos-e-simulados\/cadernos\/0351569c-fbca-473d-b289-7ce9d0f74fab\" target=\"_blank\" rel=\"noreferrer noopener\">Direito Administrativo<br \/><\/a><a href=\"https:\/\/concursos.estrategia.com\/cadernos-e-simulados\/cadernos\/1f68e282-4514-4118-a069-f95aca76d44a\" target=\"_blank\" rel=\"noreferrer noopener\">Direito Penal<br \/><\/a><a href=\"https:\/\/concursos.estrategia.com\/cadernos-e-simulados\/cadernos\/33bb9b2d-ac57-445a-8d0b-7f48c271c3a0\" target=\"_blank\" rel=\"noreferrer noopener\">Arquitetura de Computadores<br \/><\/a><a href=\"https:\/\/concursos.estrategia.com\/cadernos-e-simulados\/cadernos\/8cd2c8ba-6d0c-4ed8-bc2c-695df7c7e992\" target=\"_blank\" rel=\"noreferrer noopener\">Engenharia de Software<br \/><\/a><a href=\"https:\/\/concursos.estrategia.com\/cadernos-e-simulados\/cadernos\/4687e062-69be-45dd-9fac-f340c0153ed9\" target=\"_blank\" rel=\"noreferrer noopener\">Governan\u00e7a de TI<br \/><\/a><a href=\"https:\/\/concursos.estrategia.com\/cadernos-e-simulados\/cadernos\/6d418123-a759-42fc-81a0-89cb88bcc8da\" target=\"_blank\" rel=\"noreferrer noopener\">Redes e Seguran\u00e7a<br \/><\/a><a href=\"https:\/\/concursos.estrategia.com\/cadernos-e-simulados\/cadernos\/6d1d7fa4-eb7b-4db6-8a6b-d820682bac61\" target=\"_blank\" rel=\"noreferrer noopener\">Desenvolvimento de Software<\/a><\/p>\n\n\n\n<p><strong><\/strong><strong>Auditor de Controle Externo &#8211; <\/strong>Administra\u00e7\u00e3o<\/p>\n\n\n\n<p><a href=\"https:\/\/concursos.estrategia.com\/cadernos-e-simulados\/cadernos\/20c9cac3-42ed-406a-a3f9-9ad3dd0ed9e5\" target=\"_blank\" rel=\"noreferrer noopener\">L\u00edngua Portuguesa<br \/><\/a><a href=\"https:\/\/concursos.estrategia.com\/cadernos-e-simulados\/cadernos\/05218848-ad93-46fc-85c3-c3b7f75d13e9\" target=\"_blank\" rel=\"noreferrer noopener\">Racioc\u00ednio L\u00f3gico<br \/><\/a><a href=\"https:\/\/concursos.estrategia.com\/cadernos-e-simulados\/cadernos\/2b55b889-6038-4a2f-b139-4431ca69703e\" target=\"_blank\" rel=\"noreferrer noopener\">Estatuto dos Servidores P\u00fablicos do Munic\u00edpio de SP<br \/><\/a><a href=\"https:\/\/concursos.estrategia.com\/cadernos-e-simulados\/cadernos\/abdae964-3f60-4a37-9ff7-e448764e55cf\" target=\"_blank\" rel=\"noreferrer noopener\">Auditoria<\/a><br \/><a href=\"https:\/\/concursos.estrategia.com\/cadernos-e-simulados\/cadernos\/c52db97b-b88f-417f-b597-16eb63be6547\" target=\"_blank\" rel=\"noreferrer noopener\">Contabilidade Geral<\/a><br \/><a href=\"https:\/\/concursos.estrategia.com\/cadernos-e-simulados\/cadernos\/175c81fe-1503-4efd-bd70-6a421814f7a2\" target=\"_blank\" rel=\"noreferrer noopener\">An\u00e1lise das Demonstra\u00e7\u00f5es Cont\u00e1beis<br \/><\/a><a href=\"https:\/\/concursos.estrategia.com\/cadernos-e-simulados\/cadernos\/ce49d0d0-463a-4d4b-84d6-eb856d660134\" target=\"_blank\" rel=\"noreferrer noopener\">Or\u00e7amento P\u00fablico<br \/><\/a><a href=\"https:\/\/concursos.estrategia.com\/cadernos-e-simulados\/cadernos\/c6754946-0cd6-4ef6-a911-bd10f2467811\" target=\"_blank\" rel=\"noreferrer noopener\">Contabilidade P\u00fablica<br \/><\/a><a href=\"https:\/\/concursos.estrategia.com\/cadernos-e-simulados\/cadernos\/7eda5249-c4c6-44e0-b83e-72ae2c059899\" target=\"_blank\" rel=\"noreferrer noopener\">Controle Externo na Gest\u00e3o P\u00fablica<br \/><\/a><a href=\"https:\/\/concursos.estrategia.com\/cadernos-e-simulados\/cadernos\/0d71a46c-4123-49e3-b871-c33b487da3a4\" target=\"_blank\" rel=\"noreferrer noopener\">Direito Constitucional e Lei Org\u00e2nica<\/a><br \/><a href=\"https:\/\/concursos.estrategia.com\/cadernos-e-simulados\/cadernos\/0fc37dbb-665b-45fa-8a7f-f4a6fa10e460\" target=\"_blank\" rel=\"noreferrer noopener\">Direito Administrativo<br \/><\/a><a href=\"https:\/\/concursos.estrategia.com\/cadernos-e-simulados\/cadernos\/1f68e282-4514-4118-a069-f95aca76d44a\" target=\"_blank\" rel=\"noreferrer noopener\">Direito Penal<br \/><\/a><a href=\"https:\/\/concursos.estrategia.com\/cadernos-e-simulados\/cadernos\/b5c0200c-4eb5-4ed0-9997-96e7f4247214\" target=\"_blank\" rel=\"noreferrer noopener\">Administra\u00e7\u00e3o Geral<br \/><\/a><a href=\"https:\/\/concursos.estrategia.com\/cadernos-e-simulados\/cadernos\/1f075fe3-098e-42ad-8dfb-af22ed5cb3c8\" target=\"_blank\" rel=\"noreferrer noopener\">Administra\u00e7\u00e3o de Materiais e Log\u00edstica<br \/><\/a><a href=\"https:\/\/concursos.estrategia.com\/cadernos-e-simulados\/cadernos\/3fad23ab-3d17-4d28-b98e-77dfb910ae56\" target=\"_blank\" rel=\"noreferrer noopener\">Administra\u00e7\u00e3o P\u00fablica<\/a><\/p>\n\n\n\n<p><strong><\/strong><strong>Auditor de Controle Externo &#8211; <\/strong>Economia<\/p>\n\n\n\n<p><a href=\"https:\/\/concursos.estrategia.com\/cadernos-e-simulados\/cadernos\/20c9cac3-42ed-406a-a3f9-9ad3dd0ed9e5\" target=\"_blank\" rel=\"noreferrer noopener\">L\u00edngua Portuguesa<br \/><\/a><a href=\"https:\/\/concursos.estrategia.com\/cadernos-e-simulados\/cadernos\/05218848-ad93-46fc-85c3-c3b7f75d13e9\" target=\"_blank\" rel=\"noreferrer noopener\">Racioc\u00ednio L\u00f3gico<br \/><\/a><a href=\"https:\/\/concursos.estrategia.com\/cadernos-e-simulados\/cadernos\/0820493c-b820-46f5-95f4-43d58fe604e6\" target=\"_blank\" rel=\"noreferrer noopener\">Administra\u00e7\u00e3o<\/a><br \/><a href=\"https:\/\/concursos.estrategia.com\/cadernos-e-simulados\/cadernos\/abdae964-3f60-4a37-9ff7-e448764e55cf\" target=\"_blank\" rel=\"noreferrer noopener\">Auditoria<\/a><br \/><a href=\"https:\/\/concursos.estrategia.com\/cadernos-e-simulados\/cadernos\/c52db97b-b88f-417f-b597-16eb63be6547\" target=\"_blank\" rel=\"noreferrer noopener\">Contabilidade Geral<br \/><\/a><a href=\"https:\/\/concursos.estrategia.com\/cadernos-e-simulados\/cadernos\/13629d5d-f785-4172-a3d1-0d287915f462\" target=\"_blank\" rel=\"noreferrer noopener\">Or\u00e7amento P\u00fablico<br \/><\/a><a href=\"https:\/\/concursos.estrategia.com\/cadernos-e-simulados\/cadernos\/c6754946-0cd6-4ef6-a911-bd10f2467811\" target=\"_blank\" rel=\"noreferrer noopener\">Contabilidade P\u00fablica<br \/><\/a><a href=\"https:\/\/concursos.estrategia.com\/cadernos-e-simulados\/cadernos\/7eda5249-c4c6-44e0-b83e-72ae2c059899\" target=\"_blank\" rel=\"noreferrer noopener\">Controle Externo na Gest\u00e3o P\u00fablica<br \/><\/a><a href=\"https:\/\/concursos.estrategia.com\/cadernos-e-simulados\/cadernos\/0d71a46c-4123-49e3-b871-c33b487da3a4\" target=\"_blank\" rel=\"noreferrer noopener\">Direito Constitucional e Lei Org\u00e2nica<br \/><\/a><a href=\"https:\/\/concursos.estrategia.com\/cadernos-e-simulados\/cadernos\/0351569c-fbca-473d-b289-7ce9d0f74fab\" target=\"_blank\" rel=\"noreferrer noopener\">Direito Administrativo<br \/><\/a><a href=\"https:\/\/concursos.estrategia.com\/cadernos-e-simulados\/cadernos\/9cf27537-6181-4da9-a843-8e55ec0463d6\" target=\"_blank\" rel=\"noreferrer noopener\">Economia<\/a><br \/><a href=\"https:\/\/concursos.estrategia.com\/cadernos-e-simulados\/cadernos\/2b55b889-6038-4a2f-b139-4431ca69703e\" target=\"_blank\" rel=\"noreferrer noopener\">Estatuto dos Servidores P\u00fablicos do Munic\u00edpio de SP<br \/><\/a><a href=\"https:\/\/concursos.estrategia.com\/cadernos-e-simulados\/cadernos\/8a32c4e7-df45-44c7-9d4b-23db41cdfa94\" target=\"_blank\" rel=\"noreferrer noopener\">Estat\u00edstica Econ\u00f4mica<br \/><\/a><a href=\"https:\/\/concursos.estrategia.com\/cadernos-e-simulados\/cadernos\/1f68e282-4514-4118-a069-f95aca76d44a\" target=\"_blank\" rel=\"noreferrer noopener\">Direito Penal<br \/><\/a><a href=\"https:\/\/concursos.estrategia.com\/cadernos-e-simulados\/cadernos\/175c81fe-1503-4efd-bd70-6a421814f7a2\" target=\"_blank\" rel=\"noreferrer noopener\">An\u00e1lise das Demonstra\u00e7\u00f5es Cont\u00e1beis<\/a><\/p>\n\n\n\n<p><strong><\/strong><strong>Auditor de Controle Externo &#8211; <\/strong>Ci\u00eancias Jur\u00eddicas<\/p>\n\n\n\n<p><a href=\"https:\/\/concursos.estrategia.com\/cadernos-e-simulados\/cadernos\/20c9cac3-42ed-406a-a3f9-9ad3dd0ed9e5\" target=\"_blank\" rel=\"noreferrer noopener\">L\u00edngua Portuguesa<br \/><\/a><a href=\"https:\/\/concursos.estrategia.com\/cadernos-e-simulados\/cadernos\/05218848-ad93-46fc-85c3-c3b7f75d13e9\" target=\"_blank\" rel=\"noreferrer noopener\">Racioc\u00ednio L\u00f3gico<br \/><\/a><a href=\"https:\/\/concursos.estrategia.com\/cadernos-e-simulados\/cadernos\/0820493c-b820-46f5-95f4-43d58fe604e6\" target=\"_blank\" rel=\"noreferrer noopener\">Administra\u00e7\u00e3o<\/a><br \/><a href=\"https:\/\/concursos.estrategia.com\/cadernos-e-simulados\/cadernos\/abdae964-3f60-4a37-9ff7-e448764e55cf\" target=\"_blank\" rel=\"noreferrer noopener\">Auditoria<\/a><br \/><a href=\"https:\/\/concursos.estrategia.com\/cadernos-e-simulados\/cadernos\/c52db97b-b88f-417f-b597-16eb63be6547\" target=\"_blank\" rel=\"noreferrer noopener\">Contabilidade Geral<\/a><br \/><a href=\"https:\/\/concursos.estrategia.com\/cadernos-e-simulados\/cadernos\/83d22704-ecfe-4b36-b662-28451b63e86b\" target=\"_blank\" rel=\"noreferrer noopener\">Or\u00e7amento P\u00fablico<br \/><\/a><a href=\"https:\/\/concursos.estrategia.com\/cadernos-e-simulados\/cadernos\/c6754946-0cd6-4ef6-a911-bd10f2467811\" target=\"_blank\" rel=\"noreferrer noopener\">Contabilidade P\u00fablica<br \/><\/a><a href=\"https:\/\/concursos.estrategia.com\/cadernos-e-simulados\/cadernos\/7eda5249-c4c6-44e0-b83e-72ae2c059899\" target=\"_blank\" rel=\"noreferrer noopener\">Controle Externo na Gest\u00e3o P\u00fablica<br \/><\/a><a href=\"https:\/\/concursos.estrategia.com\/cadernos-e-simulados\/cadernos\/49b9442b-2a2f-4e50-aa0b-c857079b4bc6\" target=\"_blank\" rel=\"noreferrer noopener\">Direito Constitucional e Lei Org\u00e2nica<br \/><\/a><a href=\"https:\/\/concursos.estrategia.com\/cadernos-e-simulados\/cadernos\/989214d5-fd9a-47b7-9666-23afaf67ce4e\" target=\"_blank\" rel=\"noreferrer noopener\">Direito Administrativo<br \/><\/a><a href=\"https:\/\/concursos.estrategia.com\/cadernos-e-simulados\/cadernos\/f15da106-051f-4f64-9568-c7f26706732e\" target=\"_blank\" rel=\"noreferrer noopener\">Direito Tribut\u00e1rio<br \/><\/a><a href=\"https:\/\/concursos.estrategia.com\/cadernos-e-simulados\/cadernos\/43ff0dc1-a67f-4378-beeb-7b49cfef93f2\" target=\"_blank\" rel=\"noreferrer noopener\">Direito Urban\u00edstico<br \/><\/a><a href=\"https:\/\/concursos.estrategia.com\/cadernos-e-simulados\/cadernos\/cb696366-0726-46c3-9210-db64873a56e5\" target=\"_blank\" rel=\"noreferrer noopener\">Direito Civil<br \/><\/a><a href=\"https:\/\/concursos.estrategia.com\/cadernos-e-simulados\/cadernos\/ac03cc31-5bfc-4c8e-ac22-5cf352ca5295\" target=\"_blank\" rel=\"noreferrer noopener\">Direito Penal<br \/><\/a><a href=\"https:\/\/concursos.estrategia.com\/cadernos-e-simulados\/cadernos\/dd3568f9-1f1c-4693-ae47-e8b885520f22\" target=\"_blank\" rel=\"noreferrer noopener\">Legisla\u00e7\u00e3o Penal Especial<br \/><\/a><a href=\"https:\/\/concursos.estrategia.com\/cadernos-e-simulados\/cadernos\/3224c89d-bd3e-4771-a3bf-da9e11bfb8c9\" target=\"_blank\" rel=\"noreferrer noopener\">Direito Processual Civil<\/a><\/p>\n\n\n\n<p><strong><\/strong><strong>Auditor de Controle Externo &#8211;<\/strong> L\u00edngua Portuguesa<\/p>\n\n\n\n<p><a href=\"https:\/\/concursos.estrategia.com\/cadernos-e-simulados\/cadernos\/20c9cac3-42ed-406a-a3f9-9ad3dd0ed9e5\" target=\"_blank\" rel=\"noreferrer noopener\">L\u00edngua Portuguesa<br \/><\/a><a href=\"https:\/\/concursos.estrategia.com\/cadernos-e-simulados\/cadernos\/05218848-ad93-46fc-85c3-c3b7f75d13e9\" target=\"_blank\" rel=\"noreferrer noopener\">Racioc\u00ednio L\u00f3gico<br \/><\/a><a href=\"https:\/\/concursos.estrategia.com\/cadernos-e-simulados\/cadernos\/2b55b889-6038-4a2f-b139-4431ca69703e\" target=\"_blank\" rel=\"noreferrer noopener\">Estatuto dos Servidores P\u00fablicos do Munic\u00edpio de SP<br \/><\/a><a href=\"https:\/\/concursos.estrategia.com\/cadernos-e-simulados\/cadernos\/1f68e282-4514-4118-a069-f95aca76d44a\" target=\"_blank\" rel=\"noreferrer noopener\">Direito Penal<br \/><\/a><a href=\"https:\/\/concursos.estrategia.com\/cadernos-e-simulados\/cadernos\/d86a9653-5088-402d-822a-590898792272\" target=\"_blank\" rel=\"noreferrer noopener\">Reda\u00e7\u00e3o Oficial<br \/><\/a><a href=\"https:\/\/concursos.estrategia.com\/cadernos-e-simulados\/cadernos\/0820493c-b820-46f5-95f4-43d58fe604e6\" target=\"_blank\" rel=\"noreferrer noopener\">Administra\u00e7\u00e3o<\/a><br \/><a href=\"https:\/\/concursos.estrategia.com\/cadernos-e-simulados\/cadernos\/13629d5d-f785-4172-a3d1-0d287915f462\" target=\"_blank\" rel=\"noreferrer noopener\">Or\u00e7amento P\u00fablico<br \/><\/a><a href=\"https:\/\/concursos.estrategia.com\/cadernos-e-simulados\/cadernos\/c52db97b-b88f-417f-b597-16eb63be6547\" target=\"_blank\" rel=\"noreferrer noopener\">Contabilidade Geral<br \/><\/a><a href=\"https:\/\/concursos.estrategia.com\/cadernos-e-simulados\/cadernos\/c6754946-0cd6-4ef6-a911-bd10f2467811\" target=\"_blank\" rel=\"noreferrer noopener\">Contabilidade P\u00fablica<br \/><\/a><a href=\"https:\/\/concursos.estrategia.com\/cadernos-e-simulados\/cadernos\/0351569c-fbca-473d-b289-7ce9d0f74fab\" target=\"_blank\" rel=\"noreferrer noopener\">Direito Administrativo<br \/><\/a><a href=\"https:\/\/concursos.estrategia.com\/cadernos-e-simulados\/cadernos\/7eda5249-c4c6-44e0-b83e-72ae2c059899\" target=\"_blank\" rel=\"noreferrer noopener\">Controle Externo na Gest\u00e3o P\u00fablica<br \/><\/a><a href=\"https:\/\/concursos.estrategia.com\/cadernos-e-simulados\/cadernos\/9cd93835-5b64-46f2-abfe-c0c94ec5fd20\" target=\"_blank\" rel=\"noreferrer noopener\">Teoria Geral do Processo<br \/><\/a><a href=\"https:\/\/concursos.estrategia.com\/cadernos-e-simulados\/cadernos\/175c81fe-1503-4efd-bd70-6a421814f7a2\" target=\"_blank\" rel=\"noreferrer noopener\">An\u00e1lise das Demonstra\u00e7\u00f5es Cont\u00e1beis<br \/><\/a><a href=\"https:\/\/concursos.estrategia.com\/cadernos-e-simulados\/cadernos\/abdae964-3f60-4a37-9ff7-e448764e55cf\" target=\"_blank\" rel=\"noreferrer noopener\">Auditoria<\/a><br \/><a href=\"https:\/\/concursos.estrategia.com\/cadernos-e-simulados\/cadernos\/0d71a46c-4123-49e3-b871-c33b487da3a4\" target=\"_blank\" rel=\"noreferrer noopener\">Direito Constitucional e Lei Org\u00e2nica<\/a><\/p>\n\n\n\n<p><strong><\/strong><strong>Auditor de Controle Externo &#8211; <\/strong>Ci\u00eancias Cont\u00e1beis<\/p>\n\n\n\n<p><a href=\"https:\/\/concursos.estrategia.com\/cadernos-e-simulados\/cadernos\/20c9cac3-42ed-406a-a3f9-9ad3dd0ed9e5\" target=\"_blank\" rel=\"noreferrer noopener\">L\u00edngua Portuguesa<br \/><\/a><a href=\"https:\/\/concursos.estrategia.com\/cadernos-e-simulados\/cadernos\/05218848-ad93-46fc-85c3-c3b7f75d13e9\" target=\"_blank\" rel=\"noreferrer noopener\">Racioc\u00ednio L\u00f3gico<br \/><\/a><a href=\"https:\/\/concursos.estrategia.com\/cadernos-e-simulados\/cadernos\/2b55b889-6038-4a2f-b139-4431ca69703e\" target=\"_blank\" rel=\"noreferrer noopener\">Estatuto dos Servidores P\u00fablicos do Munic\u00edpio de SP<br \/><\/a><a href=\"https:\/\/concursos.estrategia.com\/cadernos-e-simulados\/cadernos\/0d71a46c-4123-49e3-b871-c33b487da3a4\" target=\"_blank\" rel=\"noreferrer noopener\">Direito Constitucional e Lei Org\u00e2nica<br \/><\/a><a href=\"https:\/\/concursos.estrategia.com\/cadernos-e-simulados\/cadernos\/ec9c9979-b92b-43d4-bfbd-aacf1fe30c5b\" target=\"_blank\" rel=\"noreferrer noopener\">Contabilidade P\u00fablica<br \/><\/a><a href=\"https:\/\/concursos.estrategia.com\/cadernos-e-simulados\/cadernos\/0b99d639-0ca1-4a95-b672-8d4ab4f8a2b3\" target=\"_blank\" rel=\"noreferrer noopener\">Or\u00e7amento P\u00fablico<br \/><\/a><a href=\"https:\/\/concursos.estrategia.com\/cadernos-e-simulados\/cadernos\/1f68e282-4514-4118-a069-f95aca76d44a\" target=\"_blank\" rel=\"noreferrer noopener\">Direito Penal<br \/><\/a><a href=\"https:\/\/concursos.estrategia.com\/cadernos-e-simulados\/cadernos\/abdae964-3f60-4a37-9ff7-e448764e55cf\" target=\"_blank\" rel=\"noreferrer noopener\">Auditoria<\/a><br \/><a href=\"https:\/\/concursos.estrategia.com\/cadernos-e-simulados\/cadernos\/0351569c-fbca-473d-b289-7ce9d0f74fab\" target=\"_blank\" rel=\"noreferrer noopener\">Direito Administrativo<br \/><\/a><a href=\"https:\/\/concursos.estrategia.com\/cadernos-e-simulados\/cadernos\/38007d07-f9d9-4d90-973c-d678fe9077bb\" target=\"_blank\" rel=\"noreferrer noopener\">Contabilidade Geral<br \/><\/a><a href=\"https:\/\/concursos.estrategia.com\/cadernos-e-simulados\/cadernos\/4fd7e48a-597a-4c85-9b07-34c3f3dc4fde\" target=\"_blank\" rel=\"noreferrer noopener\">Contabilidade de Custos<br \/><\/a><a href=\"https:\/\/concursos.estrategia.com\/cadernos-e-simulados\/cadernos\/7eda5249-c4c6-44e0-b83e-72ae2c059899\" target=\"_blank\" rel=\"noreferrer noopener\">Controle Externo na Gest\u00e3o P\u00fablica<br \/><\/a><a href=\"https:\/\/concursos.estrategia.com\/cadernos-e-simulados\/cadernos\/2cca8d29-a674-4f66-a598-f0a41ded16d1\" target=\"_blank\" rel=\"noreferrer noopener\">An\u00e1lise das Demonstra\u00e7\u00f5es Cont\u00e1beis<br \/><\/a><a href=\"https:\/\/concursos.estrategia.com\/cadernos-e-simulados\/cadernos\/0820493c-b820-46f5-95f4-43d58fe604e6\" target=\"_blank\" rel=\"noreferrer noopener\">Administra\u00e7\u00e3o<\/a><\/p>\n\n\n\n<p><strong><\/strong><strong>Auditor de Controle Externo &#8211; <\/strong>Ci\u00eancias Atuariais<\/p>\n\n\n\n<p><a href=\"https:\/\/concursos.estrategia.com\/cadernos-e-simulados\/cadernos\/20c9cac3-42ed-406a-a3f9-9ad3dd0ed9e5\" target=\"_blank\" rel=\"noreferrer noopener\">L\u00edngua Portuguesa<br \/><\/a><a href=\"https:\/\/concursos.estrategia.com\/cadernos-e-simulados\/cadernos\/05218848-ad93-46fc-85c3-c3b7f75d13e9\" target=\"_blank\" rel=\"noreferrer noopener\">Racioc\u00ednio L\u00f3gico<br \/><\/a><a href=\"https:\/\/concursos.estrategia.com\/cadernos-e-simulados\/cadernos\/2b55b889-6038-4a2f-b139-4431ca69703e\" target=\"_blank\" rel=\"noreferrer noopener\">Estatuto dos Servidores P\u00fablicos do Munic\u00edpio de SP<br \/><\/a><a href=\"https:\/\/concursos.estrategia.com\/cadernos-e-simulados\/cadernos\/0820493c-b820-46f5-95f4-43d58fe604e6\" target=\"_blank\" rel=\"noreferrer noopener\">Administra\u00e7\u00e3o<\/a><br \/><a href=\"https:\/\/concursos.estrategia.com\/cadernos-e-simulados\/cadernos\/abdae964-3f60-4a37-9ff7-e448764e55cf\" target=\"_blank\" rel=\"noreferrer noopener\">Auditoria<\/a><br \/><a href=\"https:\/\/concursos.estrategia.com\/cadernos-e-simulados\/cadernos\/c52db97b-b88f-417f-b597-16eb63be6547\" target=\"_blank\" rel=\"noreferrer noopener\">Contabilidade Geral<br \/><\/a><a href=\"https:\/\/concursos.estrategia.com\/cadernos-e-simulados\/cadernos\/175c81fe-1503-4efd-bd70-6a421814f7a2\" target=\"_blank\" rel=\"noreferrer noopener\">An\u00e1lise das Demonstra\u00e7\u00f5es Cont\u00e1beis<br \/><\/a><a href=\"https:\/\/concursos.estrategia.com\/cadernos-e-simulados\/cadernos\/13629d5d-f785-4172-a3d1-0d287915f462\" target=\"_blank\" rel=\"noreferrer noopener\">Or\u00e7amento P\u00fablico<br \/><\/a><a href=\"https:\/\/concursos.estrategia.com\/cadernos-e-simulados\/cadernos\/c6754946-0cd6-4ef6-a911-bd10f2467811\" target=\"_blank\" rel=\"noreferrer noopener\">Contabilidade P\u00fablica<br \/><\/a><a href=\"https:\/\/concursos.estrategia.com\/cadernos-e-simulados\/cadernos\/98f449a0-31e3-43c0-9e00-2e830951f9d4\" target=\"_blank\" rel=\"noreferrer noopener\">Direito Previdenci\u00e1rio<br \/><\/a><a href=\"https:\/\/concursos.estrategia.com\/cadernos-e-simulados\/cadernos\/9ab174af-9d47-4505-851d-ce4e5bf8eec9\" target=\"_blank\" rel=\"noreferrer noopener\">Estat\u00edstica<\/a><br \/><a href=\"https:\/\/concursos.estrategia.com\/cadernos-e-simulados\/cadernos\/e9a8d91c-cb63-4823-a693-804ca71656b9\" target=\"_blank\" rel=\"noreferrer noopener\">Matem\u00e1tica Financeira<br \/><\/a><a href=\"https:\/\/concursos.estrategia.com\/cadernos-e-simulados\/cadernos\/0d71a46c-4123-49e3-b871-c33b487da3a4\" target=\"_blank\" rel=\"noreferrer noopener\">Direito Constitucional e Lei Org\u00e2nica<br \/><\/a><a href=\"https:\/\/concursos.estrategia.com\/cadernos-e-simulados\/cadernos\/7eda5249-c4c6-44e0-b83e-72ae2c059899\" target=\"_blank\" rel=\"noreferrer noopener\">Controle Externo na Administra\u00e7\u00e3o P\u00fablica<\/a><br \/><a href=\"https:\/\/concursos.estrategia.com\/cadernos-e-simulados\/cadernos\/1f68e282-4514-4118-a069-f95aca76d44a\" target=\"_blank\" rel=\"noreferrer noopener\">Direito Penal<\/a><a href=\"https:\/\/concursos.estrategia.com\/cadernos-e-simulados\/cadernos\/7eda5249-c4c6-44e0-b83e-72ae2c059899\" target=\"_blank\" rel=\"noreferrer noopener\"><br \/><\/a><a href=\"https:\/\/concursos.estrategia.com\/cadernos-e-simulados\/cadernos\/0351569c-fbca-473d-b289-7ce9d0f74fab\" target=\"_blank\" rel=\"noreferrer noopener\">Direito Administrativo<br \/><\/a><a href=\"https:\/\/concursos.estrategia.com\/cadernos-e-simulados\/cadernos\/0d71a46c-4123-49e3-b871-c33b487da3a4\" target=\"_blank\" rel=\"noreferrer noopener\">Controle Externo na Gest\u00e3o P\u00fablica<\/a><\/p>\n\n\n\n<p><strong><\/strong><strong>Auditor de Controle Externo &#8211; <\/strong>Engenharia Civil<\/p>\n\n\n\n<p><a href=\"https:\/\/concursos.estrategia.com\/cadernos-e-simulados\/cadernos\/20c9cac3-42ed-406a-a3f9-9ad3dd0ed9e5\" target=\"_blank\" rel=\"noreferrer noopener\">L\u00edngua Portuguesa<br \/><\/a><a href=\"https:\/\/concursos.estrategia.com\/cadernos-e-simulados\/cadernos\/05218848-ad93-46fc-85c3-c3b7f75d13e9\" target=\"_blank\" rel=\"noreferrer noopener\">Racioc\u00ednio L\u00f3gico<br \/><\/a><a href=\"https:\/\/concursos.estrategia.com\/cadernos-e-simulados\/cadernos\/2b55b889-6038-4a2f-b139-4431ca69703e\" target=\"_blank\" rel=\"noreferrer noopener\">Estatuto dos Servidores P\u00fablicos do Munic\u00edpio de SP<br \/><\/a><a href=\"https:\/\/concursos.estrategia.com\/cadernos-e-simulados\/cadernos\/0820493c-b820-46f5-95f4-43d58fe604e6\" target=\"_blank\" rel=\"noreferrer noopener\">Administra\u00e7\u00e3o<\/a><br \/><a href=\"https:\/\/concursos.estrategia.com\/cadernos-e-simulados\/cadernos\/abdae964-3f60-4a37-9ff7-e448764e55cf\" target=\"_blank\" rel=\"noreferrer noopener\">Auditoria<\/a><br \/><a href=\"https:\/\/concursos.estrategia.com\/cadernos-e-simulados\/cadernos\/c52db97b-b88f-417f-b597-16eb63be6547\" target=\"_blank\" rel=\"noreferrer noopener\">Contabilidade Geral<br \/><\/a><a href=\"https:\/\/concursos.estrategia.com\/cadernos-e-simulados\/cadernos\/c6754946-0cd6-4ef6-a911-bd10f2467811\" target=\"_blank\" rel=\"noreferrer noopener\">Contabilidade P\u00fablica<br \/><\/a><a href=\"https:\/\/concursos.estrategia.com\/cadernos-e-simulados\/cadernos\/13629d5d-f785-4172-a3d1-0d287915f462\" target=\"_blank\" rel=\"noreferrer noopener\">Or\u00e7amento P\u00fablico<br \/><\/a><a href=\"https:\/\/concursos.estrategia.com\/cadernos-e-simulados\/cadernos\/7eda5249-c4c6-44e0-b83e-72ae2c059899\" target=\"_blank\" rel=\"noreferrer noopener\">Controle Externo na Gest\u00e3o P\u00fablica<br \/><\/a><a href=\"https:\/\/concursos.estrategia.com\/cadernos-e-simulados\/cadernos\/0d71a46c-4123-49e3-b871-c33b487da3a4\" target=\"_blank\" rel=\"noreferrer noopener\">Direito Constitucional e Lei Org\u00e2nica<br \/><\/a><a href=\"https:\/\/concursos.estrategia.com\/cadernos-e-simulados\/cadernos\/0351569c-fbca-473d-b289-7ce9d0f74fab\" target=\"_blank\" rel=\"noreferrer noopener\">Direito Administrativo<br \/><\/a><a href=\"https:\/\/concursos.estrategia.com\/cadernos-e-simulados\/cadernos\/1f68e282-4514-4118-a069-f95aca76d44a\" target=\"_blank\" rel=\"noreferrer noopener\">Direito Penal<br \/><\/a><a href=\"https:\/\/concursos.estrategia.com\/cadernos-e-simulados\/cadernos\/7baa2810-2cb6-4ff7-bb62-718d423fa51d\" target=\"_blank\" rel=\"noreferrer noopener\">Engenharia Civil<br \/><\/a><a href=\"https:\/\/concursos.estrategia.com\/cadernos-e-simulados\/cadernos\/352b037c-7818-480a-bd38-305091e91bc8\" target=\"_blank\" rel=\"noreferrer noopener\">Legisla\u00e7\u00e3o Ambiental<\/a><\/p>\n\n\n\n<p>Basta clicar nas <em>Mat\u00e9rias<\/em> acima estando logado no nosso SQ para ser redirecionado ao respectivo <em>Caderno de Quest\u00f5es<\/em>:<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/05\/26010139\/cadernos-1.gif\" alt=\"\" class=\"wp-image-518788\" width=\"800\" height=\"471\"\/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-encontrou-algum-erro-nos-cadernos\"><mark style=\"background-color:rgba(0, 0, 0, 0);color:#5823f7\" class=\"has-inline-color\">Encontrou algum erro nos Cadernos?<\/mark><\/h2>\n\n\n\n<p>Clique no link abaixo e relate qualquer erro que tenha encontrado nos <em>Cadernos de Quest\u00f5es<\/em> deste <em>Guia<\/em>. Iremos retificar rapidamente.<\/p>\n\n\n\n<p class=\"has-text-align-center has-medium-font-size\"><em><a href=\"https:\/\/forms.gle\/5nDMFGneBJ9DjxBH7\"><strong>Quero relatar um erro!<\/strong><\/a><\/em><\/p>\n\n\n\n<p>\u00c9 o seu <em>feedback<\/em> que nos ajuda a melhorar!<\/p>\n\n\n\n<h2 class=\"has-text-align-left wp-block-heading\" id=\"h-o-que-e-o-guia-de-estudos\"><span style=\"color: #3366ff;\"><span style=\"color:#5823f7\" class=\"has-inline-color\">O que \u00e9 o Guia de Estudos?<\/span><\/span><\/h2>\n\n\n\n<p class=\"has-text-align-left\">O nosso SQ possui o maior banco de dados de quest\u00f5es de concursos comentadas por professores. Entretanto, no estudo para concurso, n\u00e3o d\u00e1 tempo de resolver todas as quest\u00f5es dispon\u00edveis. A recomenda\u00e7\u00e3o \u00e9 que voc\u00ea <strong>foque na resolu\u00e7\u00e3o daqueles exerc\u00edcios que mais tenham a ver com o estilo da sua prova <\/strong>(dificuldade, prefer\u00eancias e perfil da banca)<strong> para que possa <em><span style=\"color: #ff0000;\"><span style=\"color:#6d3cff\" class=\"has-inline-color\">otimizar o seu tempo<\/span><\/span><\/em><\/strong>.<\/p>\n\n\n\n<p>Para justamente facilitar essa &#8220;filtragem&#8221; das quest\u00f5es de acordo com as particularidades de cada edital de concurso p\u00fablico, foram criados os <em>Guias de Estudo<\/em>.<\/p>\n\n\n\n<p>Os <strong><em>Guias<\/em> s\u00e3o artigos postados no site do Estrat\u00e9gia Concursos com links para <em>Cadernos de Quest\u00f5es<\/em>, por <em>Mat\u00e9ria<\/em>, customizados de acordo com o conte\u00fado program\u00e1tico de cada edital<\/strong>.<\/p>\n\n\n\n<p><strong><span style=\"color:#5823f7\" class=\"has-inline-color\">IMPORTANTE<\/span><\/strong> : Ao clicar nas <em>Mat\u00e9rias<\/em> de cada cargo listado acima, voc\u00ea ser\u00e1 redirecionado ao respectivo <em>Caderno de Quest\u00f5es<\/em> em nosso sistema de quest\u00f5es. Para usar os <em>Guias<\/em>, voc\u00ea precisa ser assinante. Se ainda n\u00e3o for assinante, fa\u00e7a o cadastro no site e ganhe, enquanto isso, <strong><em>acesso gratuito<\/em><\/strong> por 7 dias.<\/p>\n\n\n\n<p>Clique abaixo e conhe\u00e7a o nosso <em>Sistema de Quest\u00f5es<\/em>:<\/p>\n<\/div>\n<\/div>\n\n\n\n<figure class=\"wp-block-image aligncenter size-large is-resized\"><a href=\"https:\/\/questoes.estrategiaconcursos.com.br\/\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/05\/26010257\/home-2.gif\" alt=\"\" class=\"wp-image-518790\" width=\"800\" height=\"471\"\/><\/a><\/figure>\n\n\n\n<h2 class=\"has-text-align-left wp-block-heading\" id=\"h-funcionalidades-em-desenvolvimento\"><span style=\"color: #3366ff;\"><span style=\"color:#5823f7\" class=\"has-inline-color\">Funcionalidades em Desenvolvimento<\/span><\/span><\/h2>\n\n\n\n<p class=\"has-text-align-left\">O nosso <em>Sistema de Quest\u00f5es<\/em> foi lan\u00e7ado h\u00e1 pouco tempo. E n\u00e3o paramos de crescer a cada dia. Clique abaixo e conhe\u00e7a as funcionalidades por vir e suas datas de implementa\u00e7\u00e3o:<\/p>\n\n\n\n<p class=\"has-text-align-center has-medium-font-size\"><strong><em><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/sistema-de-questoes-o-que-vem-por-ai\/\">Funcionalidades<\/a><\/em><\/strong><\/p>\n\n\n\n<p>Bons estudos!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cadernos de Quest\u00f5es elaborados, por Mat\u00e9ria,conforme o Edital do Concurso TCM SP. Acesse, neste artigo, os Cadernos de Quest\u00f5es elaborados, para cada Mat\u00e9ria, conforme o conte\u00fado program\u00e1tico do Edital TCM SP 2023. Cadernos de Quest\u00f5es TCM SP Auxiliar T\u00e9cnico de Controle Externo &#8211; Suporte Administrativo L\u00edngua PortuguesaRacioc\u00ednio L\u00f3gicoEstatuto dos Servidores P\u00fablicos do Munic\u00edpio de SPAtendimento [&hellip;]<\/p>\n","protected":false},"author":1761,"featured_media":768946,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"post_tipo":"news","footnotes":""},"categories":[214710],"tags":[],"tax_estado":[219989],"class_list":["post-520061","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tribunais-de-contas","tax_estado-sp"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.2 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Guia de Estudos para o concurso TCM SP 2023<\/title>\n<meta name=\"description\" content=\"Confira o guia de estudos que preparamos para o Concurso TCM SP. Nele, voc\u00ea encontra os cadernos de quest\u00f5es por mat\u00e9rias.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/guia-de-estudos-tcm-sp\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Guia de Estudos para o concurso TCM SP 2023\" \/>\n<meta property=\"og:description\" content=\"Confira o guia de estudos que preparamos para o Concurso TCM SP. Nele, voc\u00ea encontra os cadernos de quest\u00f5es por mat\u00e9rias.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/guia-de-estudos-tcm-sp\/\" \/>\n<meta property=\"og:site_name\" content=\"Estrat\u00e9gia Concursos\" \/>\n<meta property=\"article:published_time\" content=\"2023-01-26T11:47:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-01-26T11:47:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/06\/16180703\/sistema-de-questoes.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"168\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Sistema de Quest\u00f5es\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:site\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Sistema de Quest\u00f5es\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/guia-de-estudos-tcm-sp\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/guia-de-estudos-tcm-sp\/\"},\"author\":{\"name\":\"Sistema de Quest\u00f5es\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/4292f3258876e111e9941b95856629ba\"},\"headline\":\"Guia de Estudos para o concurso TCM SP 2023\",\"datePublished\":\"2023-01-26T11:47:00+00:00\",\"dateModified\":\"2023-01-26T11:47:56+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/guia-de-estudos-tcm-sp\/\"},\"wordCount\":1058,\"commentCount\":3,\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/guia-de-estudos-tcm-sp\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/06\/16180703\/sistema-de-questoes.jpg\",\"articleSection\":[\"Tribunais de Contas (TCU, TCE, TCM)\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/guia-de-estudos-tcm-sp\/#respond\"]}],\"copyrightYear\":\"2023\",\"copyrightHolder\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/guia-de-estudos-tcm-sp\/\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/guia-de-estudos-tcm-sp\/\",\"name\":\"Guia de Estudos para o concurso TCM SP 2023\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/guia-de-estudos-tcm-sp\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/guia-de-estudos-tcm-sp\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/06\/16180703\/sistema-de-questoes.jpg\",\"datePublished\":\"2023-01-26T11:47:00+00:00\",\"dateModified\":\"2023-01-26T11:47:56+00:00\",\"description\":\"Confira o guia de estudos que preparamos para o Concurso TCM SP. Nele, voc\u00ea encontra os cadernos de quest\u00f5es por mat\u00e9rias.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/guia-de-estudos-tcm-sp\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/guia-de-estudos-tcm-sp\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/guia-de-estudos-tcm-sp\/#primaryimage\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/06\/16180703\/sistema-de-questoes.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/06\/16180703\/sistema-de-questoes.jpg\",\"width\":300,\"height\":168,\"caption\":\"quest\u00f5es in\u00e9ditas informativo\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/guia-de-estudos-tcm-sp\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Guia de Estudos para o concurso TCM SP 2023\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"name\":\"Estrat\u00e9gia Concursos\",\"description\":\"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.\",\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\",\"name\":\"Estrat\u00e9gia Concursos\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"width\":230,\"height\":60,\"caption\":\"Estrat\u00e9gia Concursos\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/EstratConcursos\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/4292f3258876e111e9941b95856629ba\",\"name\":\"Sistema de Quest\u00f5es\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/d97558e70510c5814f1dd81e3a7f9ced312acfb9cb2a0108592e143e5e31e627?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/d97558e70510c5814f1dd81e3a7f9ced312acfb9cb2a0108592e143e5e31e627?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/d97558e70510c5814f1dd81e3a7f9ced312acfb9cb2a0108592e143e5e31e627?s=96&d=mm&r=g\",\"caption\":\"Sistema de Quest\u00f5es\"},\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/victor-tanakaestrategiaconcursos-com-br\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Guia de Estudos para o concurso TCM SP 2023","description":"Confira o guia de estudos que preparamos para o Concurso TCM SP. Nele, voc\u00ea encontra os cadernos de quest\u00f5es por mat\u00e9rias.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.estrategiaconcursos.com.br\/blog\/guia-de-estudos-tcm-sp\/","og_locale":"pt_BR","og_type":"article","og_title":"Guia de Estudos para o concurso TCM SP 2023","og_description":"Confira o guia de estudos que preparamos para o Concurso TCM SP. Nele, voc\u00ea encontra os cadernos de quest\u00f5es por mat\u00e9rias.","og_url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/guia-de-estudos-tcm-sp\/","og_site_name":"Estrat\u00e9gia Concursos","article_published_time":"2023-01-26T11:47:00+00:00","article_modified_time":"2023-01-26T11:47:56+00:00","og_image":[{"width":300,"height":168,"url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/06\/16180703\/sistema-de-questoes.jpg","type":"image\/jpeg"}],"author":"Sistema de Quest\u00f5es","twitter_card":"summary_large_image","twitter_creator":"@EstratConcursos","twitter_site":"@EstratConcursos","twitter_misc":{"Escrito por":"Sistema de Quest\u00f5es","Est. tempo de leitura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/guia-de-estudos-tcm-sp\/#article","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/guia-de-estudos-tcm-sp\/"},"author":{"name":"Sistema de Quest\u00f5es","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/4292f3258876e111e9941b95856629ba"},"headline":"Guia de Estudos para o concurso TCM SP 2023","datePublished":"2023-01-26T11:47:00+00:00","dateModified":"2023-01-26T11:47:56+00:00","mainEntityOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/guia-de-estudos-tcm-sp\/"},"wordCount":1058,"commentCount":3,"publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/guia-de-estudos-tcm-sp\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/06\/16180703\/sistema-de-questoes.jpg","articleSection":["Tribunais de Contas (TCU, TCE, TCM)"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/guia-de-estudos-tcm-sp\/#respond"]}],"copyrightYear":"2023","copyrightHolder":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/guia-de-estudos-tcm-sp\/","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/guia-de-estudos-tcm-sp\/","name":"Guia de Estudos para o concurso TCM SP 2023","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/guia-de-estudos-tcm-sp\/#primaryimage"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/guia-de-estudos-tcm-sp\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/06\/16180703\/sistema-de-questoes.jpg","datePublished":"2023-01-26T11:47:00+00:00","dateModified":"2023-01-26T11:47:56+00:00","description":"Confira o guia de estudos que preparamos para o Concurso TCM SP. Nele, voc\u00ea encontra os cadernos de quest\u00f5es por mat\u00e9rias.","breadcrumb":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/guia-de-estudos-tcm-sp\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/guia-de-estudos-tcm-sp\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/guia-de-estudos-tcm-sp\/#primaryimage","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/06\/16180703\/sistema-de-questoes.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/06\/16180703\/sistema-de-questoes.jpg","width":300,"height":168,"caption":"quest\u00f5es in\u00e9ditas informativo"},{"@type":"BreadcrumbList","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/guia-de-estudos-tcm-sp\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.estrategiaconcursos.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Guia de Estudos para o concurso TCM SP 2023"}]},{"@type":"WebSite","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","name":"Estrat\u00e9gia Concursos","description":"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.","publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization","name":"Estrat\u00e9gia Concursos","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","width":230,"height":60,"caption":"Estrat\u00e9gia Concursos"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/EstratConcursos"]},{"@type":"Person","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/4292f3258876e111e9941b95856629ba","name":"Sistema de Quest\u00f5es","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/d97558e70510c5814f1dd81e3a7f9ced312acfb9cb2a0108592e143e5e31e627?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/d97558e70510c5814f1dd81e3a7f9ced312acfb9cb2a0108592e143e5e31e627?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d97558e70510c5814f1dd81e3a7f9ced312acfb9cb2a0108592e143e5e31e627?s=96&d=mm&r=g","caption":"Sistema de Quest\u00f5es"},"url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/victor-tanakaestrategiaconcursos-com-br\/"}]}},"_links":{"self":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/520061","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/users\/1761"}],"replies":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/comments?post=520061"}],"version-history":[{"count":16,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/520061\/revisions"}],"predecessor-version":[{"id":1159367,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/520061\/revisions\/1159367"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media\/768946"}],"wp:attachment":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media?parent=520061"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/categories?post=520061"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tags?post=520061"},{"taxonomy":"tax_estado","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tax_estado?post=520061"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}