{"id":514548,"date":"2020-06-02T12:00:00","date_gmt":"2020-06-02T15:00:00","guid":{"rendered":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?p=514548"},"modified":"2020-05-28T11:27:34","modified_gmt":"2020-05-28T14:27:34","slug":"resumo-cpc-01-teste-de-recuperabilidade-veja-os-principais-pontos-deste-pronunciamento","status":"publish","type":"post","link":"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-cpc-01-teste-de-recuperabilidade-veja-os-principais-pontos-deste-pronunciamento\/","title":{"rendered":"Resumo CPC 01 \u2013 Teste de Recuperabilidade. Veja os principais pontos deste Pronunciamento"},"content":{"rendered":"\n<p class=\"has-medium-font-size\"><em>J\u00e1 tem anotado o <strong>Resumo do CPC 01 \u2013 Redu\u00e7\u00e3o ao Valor Recuper\u00e1vel dos ativos<\/strong>? N\u00e3o saia deste artigo sem saber os principais pontos deste Pronunciamento Cont\u00e1bil<\/em><\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"820\" height=\"478\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/05\/14100820\/impairment-teste-1-2.jpg\" alt=\"resumo cpc 01\" class=\"wp-image-514554\" srcset=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/05\/14100820\/impairment-teste-1-2.jpg 820w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/05\/14100820\/impairment-teste-1-2-300x175.jpg 300w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/05\/14100820\/impairment-teste-1-2-768x448.jpg 768w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/05\/14100820\/impairment-teste-1-2-610x356.jpg 610w\" sizes=\"auto, (max-width: 820px) 100vw, 820px\" \/><figcaption>Teste de Recuperabilidade<\/figcaption><\/figure><\/div>\n\n\n\n<p>Ol\u00e1 pessoal, tudo bem? Eu espero que sim!<\/p>\n\n\n\n<p>Neste artigo iremos dar prosseguimento ao projeto de <strong>resumos dos<\/strong> <strong>principais Pronunciamentos Cont\u00e1beis<\/strong> emitidos pelo Comit\u00ea de Pronunciamentos Cont\u00e1beis (CPC).<\/p>\n\n\n\n<p>No <em>post<\/em> anterior apresentamos o resumo do CPC 00: Estrutura Conceitual. <a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/?p=513471\">Confira aqui<\/a>.<\/p>\n\n\n\n<p>Reiteraremos, como sempre, a <strong>inefici\u00eancia<\/strong> de o aluno ler todos os CPCs, haja vista a extens\u00e3o de cada um deles e a quantidade de conte\u00fado irrelevante para concursos p\u00fablicos. Portanto, esta s\u00e9rie de artigos ir\u00e1 apresentar apenas os t\u00f3picos dos Pronunciamentos que podem vir a ser cobrados nos certames.<\/p>\n\n\n\n<p>Al\u00e9m disso, iremos abordar os t\u00f3picos em sua literalidade, uma vez que muitas quest\u00f5es s\u00e3o apresentadas dessa forma aos candidatos. Gostaria ainda de <strong>explica\u00e7\u00f5es mais detalhadas<\/strong>, com <strong>exemplos pr\u00e1ticos<\/strong> e resolu\u00e7\u00e3o <strong>passo a passo<\/strong> dos exerc\u00edcios?! <a href=\"https:\/\/www.estrategiaconcursos.com.br\/cursosPorMateria\/contabilidade-avancada-201\/\">Acesse aqui<\/a> nossos cursos de Contabilidade para Concursos, elaborados pelos melhores professores da \u00e1rea.<\/p>\n\n\n\n<p>Vamos ent\u00e3o ao Resumo <a href=\"http:\/\/static.cpc.aatb.com.br\/Documentos\/27_CPC_01_R1_rev%2012.pdf\">CPC 01 \u2013 Redu\u00e7\u00e3o ao Valor Recuper\u00e1vel<\/a>.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Resumo CPC 01 \u2013 Redu\u00e7\u00e3o ao Valor Recuper\u00e1vel<\/h2>\n\n\n\n<h3 class=\"wp-block-heading\">Objetivo<\/h3>\n\n\n\n<p>O objetivo deste Pronunciamento T\u00e9cnico (Resumo CPC 01) \u00e9 estabelecer procedimentos que a entidade deve aplicar para assegurar que seus ativos estejam registrados contabilmente por valor que <strong>n\u00e3o exceda seus valores de recupera\u00e7\u00e3o<\/strong>.<\/p>\n\n\n\n<p>Um ativo est\u00e1 registrado contabilmente por valor que excede seu valor de recupera\u00e7\u00e3o se o seu valor cont\u00e1bil exceder o montante a ser recuperado pelo <strong>uso<\/strong> ou pela <strong>venda<\/strong> do ativo.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Alcance<\/h3>\n\n\n\n<p>Este pronunciamento deve ser aplicado na contabiliza\u00e7\u00e3o de ajuste para perdas por desvaloriza\u00e7\u00e3o de todos os ativos, <strong>exceto<\/strong>:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>estoques;<\/li><li>ativos de contrato e ativos resultantes de custos para obter ou cumprir contratos que devem ser reconhecidos de acordo com o CPC 47 \u2013 Receita de Contrato com Cliente;<\/li><li>ativos fiscais diferidos;<\/li><li>ativos advindos de planos de benef\u00edcios a empregados;<\/li><li>instrumentos Financeiros;<\/li><li>propriedade para investimento que seja mensurada ao valor justo;<\/li><li>ativo Biol\u00f3gico e Produto Agr\u00edcola que sejam mensurados ao valor justo l\u00edquido de despesas de vender;<\/li><li>Contratos de Seguro; e<\/li><li>ativo n\u00e3o circulante mantido para venda e opera\u00e7\u00e3o descontinuada.<\/li><\/ul>\n\n\n\n<p>Este Pronunciamento T\u00e9cnico \u00e9 aplicado a ativos financeiros classificados como:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>controladas;<\/li><li>coligadas; e<\/li><li>empreendimento controlado em conjunto.<\/li><\/ul>\n\n\n\n<h3 class=\"wp-block-heading\">Defini\u00e7\u00f5es<\/h3>\n\n\n\n<p>Segundo o Resumo CPC 01, valor cont\u00e1bil \u00e9 o montante pelo qual o ativo est\u00e1 reconhecido no balan\u00e7o depois da dedu\u00e7\u00e3o de toda respectiva deprecia\u00e7\u00e3o, amortiza\u00e7\u00e3o ou exaust\u00e3o acumulada e ajuste para perdas.<\/p>\n\n\n\n<p>Unidade geradora de caixa \u00e9 o menor grupo identific\u00e1vel de ativos que gera entradas de caixa, entradas essas que s\u00e3o em grande parte independentes das entradas de caixa de outros ativos ou outros grupos de ativos.<\/p>\n\n\n\n<p>Valor depreci\u00e1vel, amortiz\u00e1vel e exaur\u00edvel \u00e9 o custo de um ativo, ou outra base que substitua o custo nas demonstra\u00e7\u00f5es cont\u00e1beis, <strong>menos seu valor residual<\/strong>.<\/p>\n\n\n\n<p>Deprecia\u00e7\u00e3o, amortiza\u00e7\u00e3o e exaust\u00e3o \u00e9 a aloca\u00e7\u00e3o sistem\u00e1tica do valor depreci\u00e1vel, amortiz\u00e1vel e exaur\u00edvel de ativos durante sua vida \u00fatil.<\/p>\n\n\n\n<p>Valor justo \u00e9 o pre\u00e7o que seria recebido pela venda de um ativo ou que seria pago pela transfer\u00eancia de um passivo em uma transa\u00e7\u00e3o n\u00e3o for\u00e7ada entre participantes do mercado na data de mensura\u00e7\u00e3o.<\/p>\n\n\n\n<p>Perda por desvaloriza\u00e7\u00e3o \u00e9 o montante pelo qual o valor cont\u00e1bil de um ativo ou de unidade geradora de caixa excede seu valor recuper\u00e1vel.<\/p>\n\n\n\n<p>Valor recuper\u00e1vel de um ativo ou de unidade geradora de caixa \u00e9 o maior montante entre o seu valor justo l\u00edquido de despesa de venda e o seu valor em uso.<\/p>\n\n\n\n<p>De acordo com o Resumo CPC 01, vida \u00fatil \u00e9:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>o per\u00edodo de tempo durante o qual a entidade espera utilizar um ativo; <strong>ou<\/strong><\/li><li>o n\u00famero de unidades de produ\u00e7\u00e3o ou de unidades semelhantes que a entidade espera obter do ativo.<\/li><\/ul>\n\n\n\n<p>Valor em uso \u00e9 o valor presente de fluxos de caixa futuros esperados que devem advir de um ativo ou de unidade geradora de caixa.<\/p>\n\n\n\n<p>O ativo est\u00e1 desvalorizado quando seu valor cont\u00e1bil excede seu valor recuper\u00e1vel.<\/p>\n\n\n\n<p>A entidade deve avaliar ao fim de cada per\u00edodo de reporte, se h\u00e1 alguma indica\u00e7\u00e3o de que um ativo possa ter sofrido desvaloriza\u00e7\u00e3o. Se houver alguma indica\u00e7\u00e3o, a entidade deve estimar o valor recuper\u00e1vel do ativo.<\/p>\n\n\n\n<p><strong>Independentemente<\/strong> de existir, ou n\u00e3o, qualquer indica\u00e7\u00e3o de redu\u00e7\u00e3o ao valor recuper\u00e1vel, a entidade deve:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>testar, <strong>no m\u00ednimo anualmente<\/strong>, a redu\u00e7\u00e3o ao valor recuper\u00e1vel de um ativo <strong>intang\u00edvel<\/strong> com <strong>vida \u00fatil indefinida<\/strong> ou de um ativo <strong>intang\u00edvel<\/strong> ainda <strong>n\u00e3o dispon\u00edvel para uso<\/strong>, comparando o seu valor cont\u00e1bil com seu valor recuper\u00e1vel. Esse teste de redu\u00e7\u00e3o ao valor recuper\u00e1vel pode ser executado a <strong>qualquer momento no per\u00edodo de um ano<\/strong>, desde que seja executado, todo ano, no <strong>mesmo per\u00edodo<\/strong>. Ativos intang\u00edveis diferentes podem ter o valor recuper\u00e1vel testado em per\u00edodos diferentes. Entretanto, se tais ativos intang\u00edveis foram inicialmente reconhecidos durante o ano corrente, devem ter a redu\u00e7\u00e3o ao valor recuper\u00e1vel testada antes do fim do ano corrente; e<\/li><li>testar, anualmente, o \u00e1gio pago por expectativa de rentabilidade futura (goodwill) em combina\u00e7\u00e3o de neg\u00f3cios.<\/li><\/ul>\n\n\n\n<h4 class=\"wp-block-heading\">Indica\u00e7\u00f5es Externas que o ativo possa ter sofrido desvaloriza\u00e7\u00e3o<\/h4>\n\n\n\n<ul class=\"wp-block-list\"><li>h\u00e1 indica\u00e7\u00f5es observ\u00e1veis de que o valor do ativo diminuiu significativamente durante o per\u00edodo, mais do que seria de se esperar como resultado da passagem do tempo ou do uso normal;<\/li><li>mudan\u00e7as significativas com efeito adverso sobre a entidade ocorreram durante o per\u00edodo, ou ocorrer\u00e3o em futuro pr\u00f3ximo, no ambiente tecnol\u00f3gico, de mercado, econ\u00f4mico ou legal, no qual a entidade opera ou no mercado para o qual o ativo \u00e9 utilizado;<\/li><li>as taxas de juros de mercado ou outras taxas de mercado de retorno sobre investimentos aumentaram durante o per\u00edodo, e esses aumentos provavelmente afetar\u00e3o a taxa de desconto utilizada no c\u00e1lculo do valor em uso de um ativo e diminuir\u00e3o materialmente o valor recuper\u00e1vel do ativo;<\/li><li>o valor cont\u00e1bil do patrim\u00f4nio l\u00edquido da entidade \u00e9 maior do que o valor de suas a\u00e7\u00f5es no mercado;<\/li><\/ul>\n\n\n\n<h4 class=\"wp-block-heading\">Indica\u00e7\u00f5es Internas que o ativo possa ter sofrido desvaloriza\u00e7\u00e3o<\/h4>\n\n\n\n<ul class=\"wp-block-list\"><li>evid\u00eancia dispon\u00edvel de obsolesc\u00eancia ou de dano f\u00edsico de um ativo;<\/li><li>mudan\u00e7as significativas, com efeito adverso sobre a entidade, ocorreram durante o per\u00edodo, ou devem ocorrer em futuro pr\u00f3ximo, na extens\u00e3o pela qual, ou na maneira na qual, um ativo \u00e9 ou ser\u00e1 utilizado. Essas mudan\u00e7as incluem o ativo que se torna inativo ou ocioso, planos para descontinuidade ou reestrutura\u00e7\u00e3o da opera\u00e7\u00e3o \u00e0 qual um ativo pertence, planos para baixa de ativo antes da data anteriormente esperada e reavalia\u00e7\u00e3o da vida \u00fatil de ativo como finita ao inv\u00e9s de indefinida; e<\/li><li>evid\u00eancia dispon\u00edvel, proveniente de relat\u00f3rio interno, que indique que o desempenho econ\u00f4mico de um ativo \u00e9 ou ser\u00e1 pior que o esperado;<\/li><\/ul>\n\n\n\n<p>Se houver indica\u00e7\u00e3o de que um ativo possa ter sofrido desvaloriza\u00e7\u00e3o, isso pode indicar que a vida \u00fatil remanescente, o m\u00e9todo de deprecia\u00e7\u00e3o, amortiza\u00e7\u00e3o e exaust\u00e3o ou o valor residual para o ativo <strong>necessitem ser revisados<\/strong> e ajustados em conson\u00e2ncia com os Pronunciamentos T\u00e9cnicos aplic\u00e1veis ao ativo, <strong>mesmo que nenhuma perda por desvaloriza\u00e7\u00e3o seja reconhecida<\/strong> para o ativo.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Mensura\u00e7\u00e3o ao Valor Recuper\u00e1vel<\/h2>\n\n\n\n<p>Nem sempre \u00e9 necess\u00e1rio determinar o valor justo l\u00edquido de despesas de venda de um ativo e seu valor em uso. Se qualquer um desses montantes exceder o valor cont\u00e1bil do ativo, este n\u00e3o tem desvaloriza\u00e7\u00e3o e, portanto, n\u00e3o \u00e9 necess\u00e1rio estimar o outro valor.<\/p>\n\n\n\n<p>Se n\u00e3o h\u00e1 raz\u00e3o para acreditar que o valor em uso de um ativo exceda materialmente seu valor justo l\u00edquido de despesas de venda, o valor justo l\u00edquido de despesas de venda do ativo pode ser considerado como seu valor recuper\u00e1vel.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Valor Justo L\u00edquido da Despesa de Venda<\/h3>\n\n\n\n<p>As despesas com a baixa, exceto as que j\u00e1 foram reconhecidas como passivo, devem ser deduzidas ao se mensurar o valor justo l\u00edquido de despesas de aliena\u00e7\u00e3o.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Valor em Uso<\/h2>\n\n\n\n<p>A estimativa do valor em uso de um ativo envolve os seguintes passos:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>estimar futuras entradas e sa\u00eddas de caixa derivadas do uso cont\u00ednuo do ativo e de sua baixa final; e<\/li><li>aplicar a taxa de desconto apropriada a esses fluxos de caixa futuros.<\/li><\/ul>\n\n\n\n<p>A estimativa de fluxos de caixa l\u00edquidos a serem recebidos (ou pagos) pela baixa de um ativo ao t\u00e9rmino de sua vida \u00fatil deve ser o montante que a entidade espera obter da baixa do ativo em transa\u00e7\u00e3o com isen\u00e7\u00e3o de interesses entre partes conhecedoras e interessadas, ap\u00f3s deduzir as despesas estimadas com a baixa.<\/p>\n\n\n\n<p>Estimativas de fluxos de caixa futuros n\u00e3o devem incluir:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>entradas ou sa\u00eddas de caixa provenientes de atividades de financiamento; ou<\/li><li>recebimentos ou pagamentos de tributos sobre a renda.<\/li><\/ul>\n\n\n\n<h4 class=\"wp-block-heading\">Moeda Estrangeira<\/h4>\n\n\n\n<p>A entidade deve traduzir o valor presente usando a taxa de c\u00e2mbio \u00e0 vista na data do c\u00e1lculo do valor em uso.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Reconhecimento e Mensura\u00e7\u00e3o da Perda por Desvaloriza\u00e7\u00e3o<\/h2>\n\n\n\n<p>Se, e somente se, o valor recuper\u00e1vel de um ativo for inferior ao seu valor cont\u00e1bil, o valor cont\u00e1bil do ativo deve ser reduzido ao seu valor recuper\u00e1vel. Essa redu\u00e7\u00e3o representa uma perda por desvaloriza\u00e7\u00e3o do ativo.<\/p>\n\n\n\n<p>A perda por desvaloriza\u00e7\u00e3o do ativo deve ser reconhecida imediatamente na demonstra\u00e7\u00e3o do resultado, <strong>a menos que o ativo tenha sido reavaliado<\/strong>. Qualquer desvaloriza\u00e7\u00e3o de ativo reavaliado deve ser tratada como diminui\u00e7\u00e3o do saldo da reavalia\u00e7\u00e3o.<\/p>\n\n\n\n<p>A perda por desvaloriza\u00e7\u00e3o de ativo n\u00e3o reavaliado deve ser reconhecida na demonstra\u00e7\u00e3o do resultado do exerc\u00edcio. Entretanto, a perda por desvaloriza\u00e7\u00e3o de ativo reavaliado deve ser reconhecida em <strong>outros resultados abrangentes<\/strong> (na reserva de reavalia\u00e7\u00e3o) na extens\u00e3o em que a perda por desvaloriza\u00e7\u00e3o n\u00e3o exceder o saldo da reavalia\u00e7\u00e3o reconhecida para o mesmo ativo. Essa perda por desvaloriza\u00e7\u00e3o sobre o ativo reavaliado reduz a reavalia\u00e7\u00e3o reconhecida para o ativo.<\/p>\n\n\n\n<p>Depois do reconhecimento da perda por desvaloriza\u00e7\u00e3o, a despesa de deprecia\u00e7\u00e3o, amortiza\u00e7\u00e3o ou exaust\u00e3o do ativo <strong>deve ser ajustada<\/strong> em per\u00edodos futuros para alocar o valor cont\u00e1bil revisado do ativo, menos seu valor residual (se houver), em base sistem\u00e1tica ao longo de sua vida \u00fatil remanescente.<\/p>\n\n\n\n<p>O valor recuper\u00e1vel de um ativo individual n\u00e3o pode ser determinado se:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>o valor em uso do ativo n\u00e3o puder ser estimado como sendo pr\u00f3ximo de seu valor justo l\u00edquido de despesas de venda (por exemplo, quando os fluxos de caixa futuros advindos do uso cont\u00ednuo do ativo n\u00e3o puderem ser estimados como sendo insignificantes); <strong>e<\/strong><\/li><li>o ativo n\u00e3o gerar entradas de caixa que s\u00e3o em grande parte independentes daquelas provenientes de outros ativos.<\/li><\/ul>\n\n\n\n<p>Nesses casos, o valor em uso e, portanto, o valor recuper\u00e1vel, somente pode ser determinado para a unidade geradora de caixa do ativo.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Exemplo<\/h4>\n\n\n\n<p>Uma entidade de minera\u00e7\u00e3o tem uma estrada de ferro particular para dar suporte \u00e0s suas atividades de minera\u00e7\u00e3o. Essa estrada pode ser vendida somente pelo valor de sucata e ela n\u00e3o gera entradas de caixa que s\u00e3o, em grande parte, independentes das entradas de caixa provenientes de outros ativos da mina.<\/p>\n\n\n\n<p><em>N\u00e3o \u00e9 poss\u00edvel estimar o valor recuper\u00e1vel da estrada de ferro privada porque seu valor em uso n\u00e3o pode ser determinado e \u00e9 provavelmente diferente do valor de sucata. Portanto, a entidade deve estimar o valor recuper\u00e1vel da unidade geradora de caixa \u00e0 qual a estrada de ferro particular pertence, isto \u00e9, a mina como um todo.<\/em><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Unidade Geradora de Caixa<\/h2>\n\n\n\n<p>Se o valor recuper\u00e1vel de um ativo individual n\u00e3o puder ser determinado, nenhuma perda por desvaloriza\u00e7\u00e3o deve ser reconhecida para o ativo se a unidade geradora de caixa \u00e0 qual est\u00e1 relacionado n\u00e3o sofrer perda por desvaloriza\u00e7\u00e3o. Isso se aplica mesmo se o valor justo l\u00edquido de despesas de venda do ativo for menor do que seu valor cont\u00e1bil.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Revers\u00e3o da Perda por Desvaloriza\u00e7\u00e3o<\/h2>\n\n\n\n<p>A entidade deve avaliar, ao t\u00e9rmino de cada per\u00edodo de reporte, se h\u00e1 alguma indica\u00e7\u00e3o de que a perda por desvaloriza\u00e7\u00e3o reconhecida em per\u00edodos anteriores para um ativo, <strong>exceto o \u00e1gio por expectativa de rentabilidade futura (goodwill)<\/strong>, possa n\u00e3o mais existir ou ter diminu\u00eddo. Se existir alguma indica\u00e7\u00e3o, a entidade deve estimar o valor recuper\u00e1vel desse ativo.<\/p>\n\n\n\n<p>Uma perda por desvaloriza\u00e7\u00e3o reconhecida em per\u00edodos anteriores para um ativo, <strong>exceto o \u00e1gio por expectativa de rentabilidade futura (goodwill)<\/strong>, deve ser revertida se, e somente se, tiver havido mudan\u00e7a nas estimativas utilizadas para determinar o valor recuper\u00e1vel do ativo desde a \u00faltima perda por desvaloriza\u00e7\u00e3o que foi reconhecida. Se esse for o caso, o valor cont\u00e1bil do ativo deve ser aumentado para seu <strong>valor recuper\u00e1vel<\/strong>. Esse aumento ocorre pela <strong>revers\u00e3o da perda por desvaloriza\u00e7\u00e3o<\/strong>.<\/p>\n\n\n\n<p>A perda por desvaloriza\u00e7\u00e3o reconhecida para o \u00e1gio por expectativa de rentabilidade futura (goodwill) <strong>n\u00e3o deve ser revertida<\/strong> em per\u00edodo subsequente.<\/p>\n\n\n\n<p>O Pronunciamento T\u00e9cnico CPC 04 \u2013 Ativo Intang\u00edvel pro\u00edbe o reconhecimento de \u00e1gio por expectativa de rentabilidade futura (goodwill) <strong>gerado internamente<\/strong>.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Finalizando<\/h2>\n\n\n\n<p>E a\u00ed, curtiu esse artigo sobre o resumo CPC 01?! Deixe seu coment\u00e1rio.<\/p>\n\n\n\n<p>Gostaria ainda de <strong>explica\u00e7\u00f5es mais detalhadas<\/strong>, com <strong>exemplos pr\u00e1ticos<\/strong> e resolu\u00e7\u00e3o <strong>passo a passo<\/strong> dos exerc\u00edcios?! <a href=\"https:\/\/www.estrategiaconcursos.com.br\/cursosPorMateria\/contabilidade-avancada-201\/\">Acesse aqui<\/a> nossos cursos de Contabilidade para Concursos, elaborados pelos melhores professores da \u00e1rea.<\/p>\n\n\n\n<p>Forte abra\u00e7o<\/p>\n\n\n\n<p>Leandro Ricardo M. Silveira<\/p>\n\n\n\n<p><strong>Instagram: <\/strong><a href=\"https:\/\/www.instagram.com\/leandro.rms12\/\">https:\/\/www.instagram.com\/leandro.rms12\/<\/a><\/p>\n\n\n\n<p class=\"has-text-align-center has-medium-font-size\"><em><strong>Assinatura Anual Ilimitada*<\/strong><\/em><\/p>\n\n\n\n<p class=\"has-text-align-center\"><em>Prepare-se com o melhor material e com quem mais aprova em Concursos P\u00fablicos em todo o pa\u00eds. Assine agora a nossa Assinatura Anual e tenha acesso ilimitado* a todos os nossos cursos.<\/em><\/p>\n\n\n\n<p style=\"font-size:22px\" class=\"has-background has-text-align-center has-luminous-vivid-amber-background-color\"><strong>ASSINE AGORA<\/strong>&nbsp;\u2013&nbsp;<a rel=\"noreferrer noopener\" href=\"https:\/\/www.estrategiaconcursos.com.br\/assinaturas\" target=\"_blank\"><strong>Assinatura Ilimitada<\/strong><\/a><\/p>\n\n\n\n<p class=\"has-text-align-center has-medium-font-size\"><em><strong>Fique por dentro de todos os concursos<\/strong><\/em>:<\/p>\n\n\n\n<p style=\"font-size:22px\" class=\"has-background has-text-align-center has-pale-cyan-blue-background-color\"><a rel=\"noreferrer noopener\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-abertos\/\" target=\"_blank\"><strong>Concursos abertos<\/strong><\/a><\/p>\n\n\n\n<p style=\"font-size:22px\" class=\"has-background has-text-align-center has-pale-cyan-blue-background-color\"><a rel=\"noreferrer noopener\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-2020\/\" target=\"_blank\"><strong>Concursos 2020<\/strong><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>J\u00e1 tem anotado o Resumo do CPC 01 \u2013 Redu\u00e7\u00e3o ao Valor Recuper\u00e1vel dos ativos? N\u00e3o saia deste artigo sem saber os principais pontos deste Pronunciamento Cont\u00e1bil Ol\u00e1 pessoal, tudo bem? Eu espero que sim! Neste artigo iremos dar prosseguimento ao projeto de resumos dos principais Pronunciamentos Cont\u00e1beis emitidos pelo Comit\u00ea de Pronunciamentos Cont\u00e1beis (CPC). [&hellip;]<\/p>\n","protected":false},"author":1668,"featured_media":514552,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"post_tipo":"article","footnotes":""},"categories":[1983],"tags":[536,187977,1145,187983],"tax_estado":[],"class_list":["post-514548","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-fiscal-estadual","tag-contabilidade","tag-cpc-01","tag-resumo","tag-teste-de-recuperabilidade"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.2 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Resumo CPC 01 \u2013 Teste de Recuperabilidade. Saiba os Principais pontos<\/title>\n<meta name=\"description\" content=\"Resumo CPC 01. Saiba os principais pontos desde Pronunciamento Cont\u00e1bil, e os itens mais cobrados nas provas de concurso.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-cpc-01-teste-de-recuperabilidade-veja-os-principais-pontos-deste-pronunciamento\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Resumo CPC 01 \u2013 Teste de Recuperabilidade. Veja os principais pontos deste Pronunciamento\" \/>\n<meta property=\"og:description\" content=\"Resumo CPC 01. Saiba os principais pontos desde Pronunciamento Cont\u00e1bil, e os itens mais cobrados nas provas de concurso.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-cpc-01-teste-de-recuperabilidade-veja-os-principais-pontos-deste-pronunciamento\/\" \/>\n<meta property=\"og:site_name\" content=\"Estrat\u00e9gia Concursos\" \/>\n<meta property=\"article:published_time\" content=\"2020-06-02T15:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/05\/14100750\/impairment-teste-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"820\" \/>\n\t<meta property=\"og:image:height\" content=\"478\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Leandro Ricardo Machado da Silveira\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:site\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Leandro Ricardo Machado da Silveira\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"12 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-cpc-01-teste-de-recuperabilidade-veja-os-principais-pontos-deste-pronunciamento\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-cpc-01-teste-de-recuperabilidade-veja-os-principais-pontos-deste-pronunciamento\/\"},\"author\":{\"name\":\"Leandro Ricardo Machado da Silveira\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/c666a44fbce7e2e70009a9c13549267a\"},\"headline\":\"Resumo CPC 01 \u2013 Teste de Recuperabilidade. Veja os principais pontos deste Pronunciamento\",\"datePublished\":\"2020-06-02T15:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-cpc-01-teste-de-recuperabilidade-veja-os-principais-pontos-deste-pronunciamento\/\"},\"wordCount\":2425,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-cpc-01-teste-de-recuperabilidade-veja-os-principais-pontos-deste-pronunciamento\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/05\/14100750\/impairment-teste-1.jpg\",\"keywords\":[\"Contabilidade\",\"cpc 01\",\"resumo\",\"teste de recuperabilidade\"],\"articleSection\":[\"Fiscal - Estadual (ICMS)\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-cpc-01-teste-de-recuperabilidade-veja-os-principais-pontos-deste-pronunciamento\/#respond\"]}],\"copyrightYear\":\"2020\",\"copyrightHolder\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-cpc-01-teste-de-recuperabilidade-veja-os-principais-pontos-deste-pronunciamento\/\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-cpc-01-teste-de-recuperabilidade-veja-os-principais-pontos-deste-pronunciamento\/\",\"name\":\"Resumo CPC 01 \u2013 Teste de Recuperabilidade. Saiba os Principais pontos\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-cpc-01-teste-de-recuperabilidade-veja-os-principais-pontos-deste-pronunciamento\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-cpc-01-teste-de-recuperabilidade-veja-os-principais-pontos-deste-pronunciamento\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/05\/14100750\/impairment-teste-1.jpg\",\"datePublished\":\"2020-06-02T15:00:00+00:00\",\"description\":\"Resumo CPC 01. Saiba os principais pontos desde Pronunciamento Cont\u00e1bil, e os itens mais cobrados nas provas de concurso.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-cpc-01-teste-de-recuperabilidade-veja-os-principais-pontos-deste-pronunciamento\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-cpc-01-teste-de-recuperabilidade-veja-os-principais-pontos-deste-pronunciamento\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-cpc-01-teste-de-recuperabilidade-veja-os-principais-pontos-deste-pronunciamento\/#primaryimage\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/05\/14100750\/impairment-teste-1.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/05\/14100750\/impairment-teste-1.jpg\",\"width\":820,\"height\":478},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-cpc-01-teste-de-recuperabilidade-veja-os-principais-pontos-deste-pronunciamento\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Resumo CPC 01 \u2013 Teste de Recuperabilidade. Veja os principais pontos deste Pronunciamento\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"name\":\"Estrat\u00e9gia Concursos\",\"description\":\"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.\",\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\",\"name\":\"Estrat\u00e9gia Concursos\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"width\":230,\"height\":60,\"caption\":\"Estrat\u00e9gia Concursos\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/EstratConcursos\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/c666a44fbce7e2e70009a9c13549267a\",\"name\":\"Leandro Ricardo Machado da Silveira\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/6fb25994d16b9649838400aa459b16c1c83f558e0fd6ebebd16da0473908b291?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/6fb25994d16b9649838400aa459b16c1c83f558e0fd6ebebd16da0473908b291?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/6fb25994d16b9649838400aa459b16c1c83f558e0fd6ebebd16da0473908b291?s=96&d=mm&r=g\",\"caption\":\"Leandro Ricardo Machado da Silveira\"},\"description\":\"Engenheiro Aeron\u00e1utico, formado pela Universidade Federal de Uberl\u00e2ndia, possui MBA em Administra\u00e7\u00e3o e Finan\u00e7as Corporativas e aprovado nos concursos de Auditor Fiscal SEFAZ-SC e SEFAZ-GO.\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/leandro_vzthotmail-com\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Resumo CPC 01 \u2013 Teste de Recuperabilidade. Saiba os Principais pontos","description":"Resumo CPC 01. Saiba os principais pontos desde Pronunciamento Cont\u00e1bil, e os itens mais cobrados nas provas de concurso.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-cpc-01-teste-de-recuperabilidade-veja-os-principais-pontos-deste-pronunciamento\/","og_locale":"pt_BR","og_type":"article","og_title":"Resumo CPC 01 \u2013 Teste de Recuperabilidade. Veja os principais pontos deste Pronunciamento","og_description":"Resumo CPC 01. Saiba os principais pontos desde Pronunciamento Cont\u00e1bil, e os itens mais cobrados nas provas de concurso.","og_url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-cpc-01-teste-de-recuperabilidade-veja-os-principais-pontos-deste-pronunciamento\/","og_site_name":"Estrat\u00e9gia Concursos","article_published_time":"2020-06-02T15:00:00+00:00","og_image":[{"width":820,"height":478,"url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/05\/14100750\/impairment-teste-1.jpg","type":"image\/jpeg"}],"author":"Leandro Ricardo Machado da Silveira","twitter_card":"summary_large_image","twitter_creator":"@EstratConcursos","twitter_site":"@EstratConcursos","twitter_misc":{"Escrito por":"Leandro Ricardo Machado da Silveira","Est. tempo de leitura":"12 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-cpc-01-teste-de-recuperabilidade-veja-os-principais-pontos-deste-pronunciamento\/#article","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-cpc-01-teste-de-recuperabilidade-veja-os-principais-pontos-deste-pronunciamento\/"},"author":{"name":"Leandro Ricardo Machado da Silveira","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/c666a44fbce7e2e70009a9c13549267a"},"headline":"Resumo CPC 01 \u2013 Teste de Recuperabilidade. Veja os principais pontos deste Pronunciamento","datePublished":"2020-06-02T15:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-cpc-01-teste-de-recuperabilidade-veja-os-principais-pontos-deste-pronunciamento\/"},"wordCount":2425,"commentCount":0,"publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-cpc-01-teste-de-recuperabilidade-veja-os-principais-pontos-deste-pronunciamento\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/05\/14100750\/impairment-teste-1.jpg","keywords":["Contabilidade","cpc 01","resumo","teste de recuperabilidade"],"articleSection":["Fiscal - Estadual (ICMS)"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-cpc-01-teste-de-recuperabilidade-veja-os-principais-pontos-deste-pronunciamento\/#respond"]}],"copyrightYear":"2020","copyrightHolder":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-cpc-01-teste-de-recuperabilidade-veja-os-principais-pontos-deste-pronunciamento\/","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-cpc-01-teste-de-recuperabilidade-veja-os-principais-pontos-deste-pronunciamento\/","name":"Resumo CPC 01 \u2013 Teste de Recuperabilidade. Saiba os Principais pontos","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-cpc-01-teste-de-recuperabilidade-veja-os-principais-pontos-deste-pronunciamento\/#primaryimage"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-cpc-01-teste-de-recuperabilidade-veja-os-principais-pontos-deste-pronunciamento\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/05\/14100750\/impairment-teste-1.jpg","datePublished":"2020-06-02T15:00:00+00:00","description":"Resumo CPC 01. Saiba os principais pontos desde Pronunciamento Cont\u00e1bil, e os itens mais cobrados nas provas de concurso.","breadcrumb":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-cpc-01-teste-de-recuperabilidade-veja-os-principais-pontos-deste-pronunciamento\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-cpc-01-teste-de-recuperabilidade-veja-os-principais-pontos-deste-pronunciamento\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-cpc-01-teste-de-recuperabilidade-veja-os-principais-pontos-deste-pronunciamento\/#primaryimage","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/05\/14100750\/impairment-teste-1.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/05\/14100750\/impairment-teste-1.jpg","width":820,"height":478},{"@type":"BreadcrumbList","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-cpc-01-teste-de-recuperabilidade-veja-os-principais-pontos-deste-pronunciamento\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.estrategiaconcursos.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Resumo CPC 01 \u2013 Teste de Recuperabilidade. Veja os principais pontos deste Pronunciamento"}]},{"@type":"WebSite","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","name":"Estrat\u00e9gia Concursos","description":"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.","publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization","name":"Estrat\u00e9gia Concursos","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","width":230,"height":60,"caption":"Estrat\u00e9gia Concursos"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/EstratConcursos"]},{"@type":"Person","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/c666a44fbce7e2e70009a9c13549267a","name":"Leandro Ricardo Machado da Silveira","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/6fb25994d16b9649838400aa459b16c1c83f558e0fd6ebebd16da0473908b291?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/6fb25994d16b9649838400aa459b16c1c83f558e0fd6ebebd16da0473908b291?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6fb25994d16b9649838400aa459b16c1c83f558e0fd6ebebd16da0473908b291?s=96&d=mm&r=g","caption":"Leandro Ricardo Machado da Silveira"},"description":"Engenheiro Aeron\u00e1utico, formado pela Universidade Federal de Uberl\u00e2ndia, possui MBA em Administra\u00e7\u00e3o e Finan\u00e7as Corporativas e aprovado nos concursos de Auditor Fiscal SEFAZ-SC e SEFAZ-GO.","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/leandro_vzthotmail-com\/"}]}},"_links":{"self":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/514548","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/users\/1668"}],"replies":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/comments?post=514548"}],"version-history":[{"count":5,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/514548\/revisions"}],"predecessor-version":[{"id":519752,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/514548\/revisions\/519752"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media\/514552"}],"wp:attachment":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media?parent=514548"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/categories?post=514548"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tags?post=514548"},{"taxonomy":"tax_estado","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tax_estado?post=514548"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}