{"id":509517,"date":"2020-05-16T14:03:00","date_gmt":"2020-05-16T17:03:00","guid":{"rendered":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?p=509517"},"modified":"2020-05-05T14:06:26","modified_gmt":"2020-05-05T17:06:26","slug":"veja-as-principais-sumulas-de-processo-civil-para-oab","status":"publish","type":"post","link":"https:\/\/www.estrategiaconcursos.com.br\/blog\/veja-as-principais-sumulas-de-processo-civil-para-oab\/","title":{"rendered":"Veja as principais S\u00famulas de Processo Civil para OAB."},"content":{"rendered":"\n<p class=\"has-medium-font-size\"><em>J\u00e1 tem anotado quais s\u00e3o as <strong>principais s\u00famulas de Processo Civil para OAB<\/strong>? N\u00e3o saia deste artigo sem sab\u00ea-las.<\/em><\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/05\/01135208\/cpc11489495421.jpg\" alt=\"s\u00famulas de processo civil para OAB\" class=\"wp-image-509521\" srcset=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/05\/01135208\/cpc11489495421.jpg 800w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/05\/01135208\/cpc11489495421-300x225.jpg 300w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/05\/01135208\/cpc11489495421-768x576.jpg 768w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/05\/01135208\/cpc11489495421-610x458.jpg 610w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><figcaption>Direito Processual Civil para OAB<\/figcaption><\/figure><\/div>\n\n\n\n<p>Ol\u00e1 pessoal, tudo bem? Eu espero que sim!<\/p>\n\n\n\n<p>Neste artigo iremos dar continuidade ao nosso projeto sobre as principais s\u00famulas do STF e do STJ para concursos p\u00fablicos. No \u00faltimo post, falamos sobre <a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/?p=509270\">direito do consumidor<\/a>. O tema da vez s\u00e3o as <strong>principais s\u00famulas de Processo Civil para OAB.<\/strong><\/p>\n\n\n\n<p>No Brasil, o direito civil \u00e9 uma das \u00e1reas mais amplas do judici\u00e1rio, fazendo necess\u00e1rio separar o estudo de direito civil do processual civil. O direito processual, nas palavras de Ada Pellegrini, \u00e9 o conjunto de princ\u00edpios e normas que regem o exerc\u00edcio da jurisdi\u00e7\u00e3o. Ou seja, \u00e9 o ramo do direito que estabelece as diretrizes para que as institui\u00e7\u00f5es pe\u00e7am ju\u00edzo de um determinado direito.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Principais S\u00famulas de Processo Civil para OAB<\/h2>\n\n\n\n<p>Vamos ent\u00e3o \u00e0s principais s\u00famulas para processo civil emitidas pelo Supremo Tribunal Federal e pelo Superior Tribunal de Justi\u00e7a. Ademais, para explica\u00e7\u00f5es detalhadas acerca das principais s\u00famulas de processo civil para OAB, juntamente com exemplos pr\u00e1ticos e exerc\u00edcios, acesse <strong><a href=\"https:\/\/www.estrategiaconcursos.com.br\/cursosPorMateria\/direito-processual-civil-43\/\">os melhores materiais para Processo Civil<\/a><\/strong>.<\/p>\n\n\n\n<p>Analogamente \u00e0 Direito Civil, n\u00e3o encontramos nenhuma S\u00famula Vinculante do STF que diga respeito primordialmente \u00e0 Processo Civil. Dessa forma, restringiremos nossos estudos \u00e0s s\u00famulas que n\u00e3o possuem efeito vinculante, em sua maioria do STJ.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">S\u00famulas STF para Processo Civil<\/h2>\n\n\n\n<p><strong>S\u00famula 216, STF<\/strong><\/p>\n\n\n\n<p>Para decreta\u00e7\u00e3o da absolvi\u00e7\u00e3o de inst\u00e2ncia pela paralisa\u00e7\u00e3o do processo por mais de trinta dias, \u00e9 necess\u00e1rio que o autor, previamente intimado, n\u00e3o promova o andamento da causa.<\/p>\n\n\n\n<p><strong>S\u00famula 249, STF<\/strong><\/p>\n\n\n\n<p>\u00c9 competente o Supremo Tribunal Federal para a a\u00e7\u00e3o rescis\u00f3ria quando, embora n\u00e3o tendo conhecido do recurso extraordin\u00e1rio, ou havendo negado provimento ao agravo, tiver apreciado a quest\u00e3o federal controvertida.<\/p>\n\n\n\n<p><strong>S\u00famula 252, STF<\/strong><\/p>\n\n\n\n<p>Na a\u00e7\u00e3o rescis\u00f3ria, n\u00e3o est\u00e3o impedidos ju\u00edzes que participaram do julgamento rescindendo.<\/p>\n\n\n\n<p><strong>S\u00famula 264, STF<\/strong><\/p>\n\n\n\n<p>Verifica-se a prescri\u00e7\u00e3o intercorrente pela paralisa\u00e7\u00e3o da a\u00e7\u00e3o rescis\u00f3ria por mais de cinco anos.<\/p>\n\n\n\n<p><strong>S\u00famula 515, STF<\/strong><\/p>\n\n\n\n<p>A compet\u00eancia para a a\u00e7\u00e3o rescis\u00f3ria n\u00e3o \u00e9 do Supremo Tribunal Federal, quando a quest\u00e3o federal, apreciada no recurso extraordin\u00e1rio ou no agravo de instrumento, seja diversa da que foi suscitada no pedido rescis\u00f3rio.<\/p>\n\n\n\n<p><strong>S\u00famula 643, STF<\/strong><\/p>\n\n\n\n<p>O Minist\u00e9rio P\u00fablico tem legitimidade para promover a\u00e7\u00e3o civil p\u00fablica cujo fundamento seja a ilegalidade de reajuste de mensalidades escolares.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">S\u00famulas STJ para Processo Civil<\/h2>\n\n\n\n<p>Por fim, vamos \u00e0s s\u00famulas de processo civil para OAB emitidas pelo Superior Tribunal de Justi\u00e7a (STJ).<\/p>\n\n\n\n<p><strong>S\u00famula 33, STJ<\/strong><\/p>\n\n\n\n<p>A incompet\u00eancia relativa n\u00e3o pode ser declarada de of\u00edcio.<\/p>\n\n\n\n<p><strong>S\u00famula 89, STJ<\/strong><\/p>\n\n\n\n<p>A a\u00e7\u00e3o acident\u00e1ria prescinde do exaurimento da via administrativa.<\/p>\n\n\n\n<p><strong>S\u00famula 106, STJ<\/strong><\/p>\n\n\n\n<p>Proposta a a\u00e7\u00e3o no prazo fixado para o seu exerc\u00edcio, a demora na cita\u00e7\u00e3o, por motivos inerentes ao mecanismo da justi\u00e7a, n\u00e3o justifica o acolhimento da argui\u00e7\u00e3o de prescri\u00e7\u00e3o ou decad\u00eancia.<\/p>\n\n\n\n<p><strong>S\u00famula 110, STJ<\/strong><\/p>\n\n\n\n<p>A isen\u00e7\u00e3o do pagamento de honor\u00e1rios advocat\u00edcios, nas a\u00e7\u00f5es acident\u00e1rias, \u00e9 restrita ao segurado.<\/p>\n\n\n\n<p><strong>S\u00famula 117, STJ<\/strong><\/p>\n\n\n\n<p>A inobserv\u00e2ncia do prazo de 48 horas, entre a publica\u00e7\u00e3o de pauta e o julgamento sem a presen\u00e7a das partes, acarreta nulidade.<\/p>\n\n\n\n<p><strong>S\u00famula 118, STJ<\/strong><\/p>\n\n\n\n<p>O agravo de instrumento \u00e9 o recurso cab\u00edvel da decis\u00e3o que homologa a atualiza\u00e7\u00e3o do c\u00e1lculo da liquida\u00e7\u00e3o.<\/p>\n\n\n\n<p><strong>S\u00famula 175, STJ<\/strong><\/p>\n\n\n\n<p>Descabe o dep\u00f3sito pr\u00e9vio nas a\u00e7\u00f5es rescis\u00f3rias propostas pelo INSS.<\/p>\n\n\n\n<p><strong>S\u00famula 181, STJ<\/strong><\/p>\n\n\n\n<p>\u00c9 admiss\u00edvel a\u00e7\u00e3o declarat\u00f3ria, visando a obter certeza quanto \u00e0 exata interpreta\u00e7\u00e3o de cl\u00e1usula contratual.<\/p>\n\n\n\n<p><strong>S\u00famula 182, STJ&nbsp;<\/strong><\/p>\n\n\n\n<p>E invi\u00e1vel o agravo do art. 545 do CPC que deixa de atacar especificamente os fundamentos da decis\u00e3o agravada.<\/p>\n\n\n\n<p><strong>S\u00famula 223, STJ<\/strong><\/p>\n\n\n\n<p>A certid\u00e3o de intima\u00e7\u00e3o do ac\u00f3rd\u00e3o recorrido constitui pe\u00e7a obrigat\u00f3ria do instrumento de agravo.<\/p>\n\n\n\n<p><strong>S\u00famula 226, STJ<\/strong><\/p>\n\n\n\n<p>O Minist\u00e9rio P\u00fablico tem legitimidade para recorrer na a\u00e7\u00e3o de acidente do trabalho, ainda que o segurado esteja assistido por advogado.<\/p>\n\n\n\n<p><strong>S\u00famula 228, STJ<\/strong><\/p>\n\n\n\n<p>\u00c9 inadmiss\u00edvel o interdito proibit\u00f3rio para a prote\u00e7\u00e3o do direito autoral.<\/p>\n\n\n\n<p><strong>S\u00famula 240, STJ<\/strong><\/p>\n\n\n\n<p>A extin\u00e7\u00e3o do processo, por abandono da causa pelo autor, depende de requerimento do r\u00e9u.<\/p>\n\n\n\n<p><strong>S\u00famula 299, STJ<\/strong><\/p>\n\n\n\n<p>\u00c9 admiss\u00edvel a a\u00e7\u00e3o monit\u00f3ria fundada em cheque prescrito.<\/p>\n\n\n\n<p><strong>S\u00famula 331, STJ<\/strong><\/p>\n\n\n\n<p>A apela\u00e7\u00e3o interposta contra senten\u00e7a que julga embargos \u00e0 arremata\u00e7\u00e3o tem efeito meramente devolutivo.<\/p>\n\n\n\n<p><strong>S\u00famula 339, STJ<\/strong><\/p>\n\n\n\n<p>\u00c9 cab\u00edvel a\u00e7\u00e3o monit\u00f3ria contra a Fazenda P\u00fablica.<\/p>\n\n\n\n<p><strong>S\u00famula 384, STJ<\/strong><\/p>\n\n\n\n<p>Cabe a\u00e7\u00e3o monit\u00f3ria para haver saldo remanescente oriundo de venda extrajudicial de bem alienado fiduciariamente em garantia.<\/p>\n\n\n\n<p><strong>S\u00famula 401, STJ<\/strong><\/p>\n\n\n\n<p>O prazo decadencial da a\u00e7\u00e3o rescis\u00f3ria s\u00f3 se inicia quando n\u00e3o for cab\u00edvel qualquer recurso do \u00faltimo pronunciamento judicial.<\/p>\n\n\n\n<p><strong>S\u00famula 429, STJ<\/strong><\/p>\n\n\n\n<p>A cita\u00e7\u00e3o postal, quando autorizada por lei, exige o aviso de recebimento.<\/p>\n\n\n\n<p><strong>S\u00famula 481, STJ<\/strong><\/p>\n\n\n\n<p>Faz jus ao benef\u00edcio da justi\u00e7a gratuita a pessoa jur\u00eddica com ou sem fins lucrativos que demonstrar sua impossibilidade de arcar com os encargos processuais.<\/p>\n\n\n\n<p><strong>S\u00famula 485, STJ<\/strong><\/p>\n\n\n\n<p>A Lei de Arbitragem aplica-se aos contratos que contenham cl\u00e1usula arbitral, ainda que celebrados antes da sua edi\u00e7\u00e3o.<\/p>\n\n\n\n<p><strong>S\u00famula 503, STJ<\/strong><\/p>\n\n\n\n<p>O prazo para ajuizamento de a\u00e7\u00e3o monit\u00f3ria em face do emitente de cheque sem for\u00e7a executiva \u00e9 quinquenal, a contar do dia seguinte \u00e0 data de emiss\u00e3o estampada na c\u00e1rtula.<\/p>\n\n\n\n<p><strong>S\u00famula 525, STJ<\/strong><\/p>\n\n\n\n<p>A C\u00e2mara de Vereadores n\u00e3o possui personalidade jur\u00eddica, apenas personalidade judici\u00e1ria, somente podendo demandar em ju\u00edzo para defender os seus direitos institucionais.<\/p>\n\n\n\n<p><strong>S\u00famula 568, STJ<\/strong><\/p>\n\n\n\n<p>O relator, monocraticamente e no Superior Tribunal de Justi\u00e7a, poder\u00e1 dar ou negar provimento ao recurso quando houver entendimento dominante acerca do tema.<\/p>\n\n\n\n<p><strong>S\u00famula 594, STJ<\/strong><\/p>\n\n\n\n<p>O Minist\u00e9rio P\u00fablico tem legitimidade ativa para ajuizar a\u00e7\u00e3o de alimentos em proveito de crian\u00e7a ou adolescente independentemente do exerc\u00edcio do poder familiar dos pais, ou do fato de o menor se encontrar nas situa\u00e7\u00f5es de risco descritas no art. 98 do Estatuto da Crian\u00e7a e do Adolescente, ou de quaisquer outros questionamentos acerca da exist\u00eancia ou efici\u00eancia da Defensoria P\u00fablica na comarca.<\/p>\n\n\n\n<p><strong>S\u00famula 637, STJ<\/strong><\/p>\n\n\n\n<p>O ente p\u00fablico det\u00e9m legitimidade e interesse para intervir, incidentalmente, na a\u00e7\u00e3o possess\u00f3ria entre particulares, podendo deduzir qualquer mat\u00e9ria defensiva, inclusive, se for o caso, o dom\u00ednio.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Finalizando<\/h2>\n\n\n\n<p>Para explica\u00e7\u00f5es detalhadas acerca das principais s\u00famulas de processo civil para OAB, juntamente com exemplos pr\u00e1ticos e exerc\u00edcios, acesse <strong><a href=\"https:\/\/www.estrategiaconcursos.com.br\/cursosPorMateria\/direito-processual-civil-43\/\">os melhores materiais para Processo Civil<\/a><\/strong>.<\/p>\n\n\n\n<p>Um forte abra\u00e7o<\/p>\n\n\n\n<p>Leandro Ricardo M. Silveira<\/p>\n\n\n\n<p><strong>Instagram: <\/strong><a href=\"https:\/\/www.instagram.com\/leandro.rms12\/\">https:\/\/www.instagram.com\/leandro.rms12\/<\/a><\/p>\n\n\n\n<p class=\"has-text-align-center has-medium-font-size\"><em><strong>Assinatura Anual Ilimitada*<\/strong><\/em><\/p>\n\n\n\n<p class=\"has-text-align-center\"><em>Prepare-se com o melhor material e com quem mais aprova em Concursos P\u00fablicos em todo o pa\u00eds. Assine agora a nossa Assinatura Anual e tenha acesso ilimitado* a todos os nossos cursos.<\/em><\/p>\n\n\n\n<p style=\"font-size:22px\" class=\"has-background has-text-align-center has-luminous-vivid-amber-background-color\"><strong>ASSINE AGORA<\/strong>&nbsp;\u2013&nbsp;<a rel=\"noreferrer noopener\" href=\"https:\/\/www.estrategiaconcursos.com.br\/assinaturas\" target=\"_blank\"><strong>Assinatura Ilimitada<\/strong><\/a><\/p>\n\n\n\n<p class=\"has-text-align-center has-medium-font-size\"><em><strong>Fique por dentro de todos os concursos<\/strong><\/em>:<\/p>\n\n\n\n<p style=\"font-size:22px\" class=\"has-background has-text-align-center has-pale-cyan-blue-background-color\"><a rel=\"noreferrer noopener\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-abertos\/\" target=\"_blank\"><strong>Concursos abertos<\/strong><\/a><\/p>\n\n\n\n<p style=\"font-size:22px\" class=\"has-background has-text-align-center has-pale-cyan-blue-background-color\"><a rel=\"noreferrer noopener\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-2020\/\" target=\"_blank\"><strong>Concursos 2020<\/strong><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>J\u00e1 tem anotado quais s\u00e3o as principais s\u00famulas de Processo Civil para OAB? N\u00e3o saia deste artigo sem sab\u00ea-las. Ol\u00e1 pessoal, tudo bem? Eu espero que sim! Neste artigo iremos dar continuidade ao nosso projeto sobre as principais s\u00famulas do STF e do STJ para concursos p\u00fablicos. No \u00faltimo post, falamos sobre direito do consumidor. [&hellip;]<\/p>\n","protected":false},"author":1668,"featured_media":509521,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"post_tipo":"article","footnotes":""},"categories":[1,2185,2017],"tags":[1698,3479,181958,3503],"tax_estado":[],"class_list":["post-509517","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cursos-e-concursos","category-carreiras-juridicas","category-concursos-legislativos","tag-jurisprudencia-stf","tag-jurisprudencia-stj","tag-sumulas-stf","tag-sumulas-stj"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.2 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Veja as principais S\u00famulas de Processo Civil para OAB.<\/title>\n<meta name=\"description\" content=\"Principais s\u00famulas de Processo Civil para OAB . Um apanhado das jurisprud\u00eancias do STF e do STJ mais cobradas em provas de concursos e da OAB.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/veja-as-principais-sumulas-de-processo-civil-para-oab\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Veja as principais S\u00famulas de Processo Civil para OAB.\" \/>\n<meta property=\"og:description\" content=\"Principais s\u00famulas de Processo Civil para OAB . Um apanhado das jurisprud\u00eancias do STF e do STJ mais cobradas em provas de concursos e da OAB.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/veja-as-principais-sumulas-de-processo-civil-para-oab\/\" \/>\n<meta property=\"og:site_name\" content=\"Estrat\u00e9gia Concursos\" \/>\n<meta property=\"article:published_time\" content=\"2020-05-16T17:03:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/05\/01135208\/cpc11489495421.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Leandro Ricardo Machado da Silveira\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:site\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Leandro Ricardo Machado da Silveira\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/veja-as-principais-sumulas-de-processo-civil-para-oab\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/veja-as-principais-sumulas-de-processo-civil-para-oab\/\"},\"author\":{\"name\":\"Leandro Ricardo Machado da Silveira\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/c666a44fbce7e2e70009a9c13549267a\"},\"headline\":\"Veja as principais S\u00famulas de Processo Civil para OAB.\",\"datePublished\":\"2020-05-16T17:03:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/veja-as-principais-sumulas-de-processo-civil-para-oab\/\"},\"wordCount\":1233,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/veja-as-principais-sumulas-de-processo-civil-para-oab\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/05\/01135208\/cpc11489495421.jpg\",\"keywords\":[\"Jurisprud\u00eancia STF\",\"Jurisprud\u00eancia STJ\",\"s\u00famulas stf\",\"S\u00famulas STJ\"],\"articleSection\":[\"Concursos P\u00fablicos\",\"Jur\u00eddico\",\"Legislativo\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/veja-as-principais-sumulas-de-processo-civil-para-oab\/#respond\"]}],\"copyrightYear\":\"2020\",\"copyrightHolder\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/veja-as-principais-sumulas-de-processo-civil-para-oab\/\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/veja-as-principais-sumulas-de-processo-civil-para-oab\/\",\"name\":\"Veja as principais S\u00famulas de Processo Civil para OAB.\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/veja-as-principais-sumulas-de-processo-civil-para-oab\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/veja-as-principais-sumulas-de-processo-civil-para-oab\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/05\/01135208\/cpc11489495421.jpg\",\"datePublished\":\"2020-05-16T17:03:00+00:00\",\"description\":\"Principais s\u00famulas de Processo Civil para OAB . Um apanhado das jurisprud\u00eancias do STF e do STJ mais cobradas em provas de concursos e da OAB.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/veja-as-principais-sumulas-de-processo-civil-para-oab\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/veja-as-principais-sumulas-de-processo-civil-para-oab\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/veja-as-principais-sumulas-de-processo-civil-para-oab\/#primaryimage\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/05\/01135208\/cpc11489495421.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/05\/01135208\/cpc11489495421.jpg\",\"width\":800,\"height\":600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/veja-as-principais-sumulas-de-processo-civil-para-oab\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Veja as principais S\u00famulas de Processo Civil para OAB.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"name\":\"Estrat\u00e9gia Concursos\",\"description\":\"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.\",\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\",\"name\":\"Estrat\u00e9gia Concursos\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"width\":230,\"height\":60,\"caption\":\"Estrat\u00e9gia Concursos\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/EstratConcursos\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/c666a44fbce7e2e70009a9c13549267a\",\"name\":\"Leandro Ricardo Machado da Silveira\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/6fb25994d16b9649838400aa459b16c1c83f558e0fd6ebebd16da0473908b291?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/6fb25994d16b9649838400aa459b16c1c83f558e0fd6ebebd16da0473908b291?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/6fb25994d16b9649838400aa459b16c1c83f558e0fd6ebebd16da0473908b291?s=96&d=mm&r=g\",\"caption\":\"Leandro Ricardo Machado da Silveira\"},\"description\":\"Engenheiro Aeron\u00e1utico, formado pela Universidade Federal de Uberl\u00e2ndia, possui MBA em Administra\u00e7\u00e3o e Finan\u00e7as Corporativas e aprovado nos concursos de Auditor Fiscal SEFAZ-SC e SEFAZ-GO.\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/leandro_vzthotmail-com\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Veja as principais S\u00famulas de Processo Civil para OAB.","description":"Principais s\u00famulas de Processo Civil para OAB . Um apanhado das jurisprud\u00eancias do STF e do STJ mais cobradas em provas de concursos e da OAB.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.estrategiaconcursos.com.br\/blog\/veja-as-principais-sumulas-de-processo-civil-para-oab\/","og_locale":"pt_BR","og_type":"article","og_title":"Veja as principais S\u00famulas de Processo Civil para OAB.","og_description":"Principais s\u00famulas de Processo Civil para OAB . Um apanhado das jurisprud\u00eancias do STF e do STJ mais cobradas em provas de concursos e da OAB.","og_url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/veja-as-principais-sumulas-de-processo-civil-para-oab\/","og_site_name":"Estrat\u00e9gia Concursos","article_published_time":"2020-05-16T17:03:00+00:00","og_image":[{"width":800,"height":600,"url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/05\/01135208\/cpc11489495421.jpg","type":"image\/jpeg"}],"author":"Leandro Ricardo Machado da Silveira","twitter_card":"summary_large_image","twitter_creator":"@EstratConcursos","twitter_site":"@EstratConcursos","twitter_misc":{"Escrito por":"Leandro Ricardo Machado da Silveira","Est. tempo de leitura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/veja-as-principais-sumulas-de-processo-civil-para-oab\/#article","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/veja-as-principais-sumulas-de-processo-civil-para-oab\/"},"author":{"name":"Leandro Ricardo Machado da Silveira","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/c666a44fbce7e2e70009a9c13549267a"},"headline":"Veja as principais S\u00famulas de Processo Civil para OAB.","datePublished":"2020-05-16T17:03:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/veja-as-principais-sumulas-de-processo-civil-para-oab\/"},"wordCount":1233,"commentCount":0,"publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/veja-as-principais-sumulas-de-processo-civil-para-oab\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/05\/01135208\/cpc11489495421.jpg","keywords":["Jurisprud\u00eancia STF","Jurisprud\u00eancia STJ","s\u00famulas stf","S\u00famulas STJ"],"articleSection":["Concursos P\u00fablicos","Jur\u00eddico","Legislativo"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/veja-as-principais-sumulas-de-processo-civil-para-oab\/#respond"]}],"copyrightYear":"2020","copyrightHolder":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/veja-as-principais-sumulas-de-processo-civil-para-oab\/","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/veja-as-principais-sumulas-de-processo-civil-para-oab\/","name":"Veja as principais S\u00famulas de Processo Civil para OAB.","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/veja-as-principais-sumulas-de-processo-civil-para-oab\/#primaryimage"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/veja-as-principais-sumulas-de-processo-civil-para-oab\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/05\/01135208\/cpc11489495421.jpg","datePublished":"2020-05-16T17:03:00+00:00","description":"Principais s\u00famulas de Processo Civil para OAB . Um apanhado das jurisprud\u00eancias do STF e do STJ mais cobradas em provas de concursos e da OAB.","breadcrumb":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/veja-as-principais-sumulas-de-processo-civil-para-oab\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/veja-as-principais-sumulas-de-processo-civil-para-oab\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/veja-as-principais-sumulas-de-processo-civil-para-oab\/#primaryimage","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/05\/01135208\/cpc11489495421.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/05\/01135208\/cpc11489495421.jpg","width":800,"height":600},{"@type":"BreadcrumbList","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/veja-as-principais-sumulas-de-processo-civil-para-oab\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.estrategiaconcursos.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Veja as principais S\u00famulas de Processo Civil para OAB."}]},{"@type":"WebSite","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","name":"Estrat\u00e9gia Concursos","description":"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.","publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization","name":"Estrat\u00e9gia Concursos","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","width":230,"height":60,"caption":"Estrat\u00e9gia Concursos"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/EstratConcursos"]},{"@type":"Person","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/c666a44fbce7e2e70009a9c13549267a","name":"Leandro Ricardo Machado da Silveira","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/6fb25994d16b9649838400aa459b16c1c83f558e0fd6ebebd16da0473908b291?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/6fb25994d16b9649838400aa459b16c1c83f558e0fd6ebebd16da0473908b291?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6fb25994d16b9649838400aa459b16c1c83f558e0fd6ebebd16da0473908b291?s=96&d=mm&r=g","caption":"Leandro Ricardo Machado da Silveira"},"description":"Engenheiro Aeron\u00e1utico, formado pela Universidade Federal de Uberl\u00e2ndia, possui MBA em Administra\u00e7\u00e3o e Finan\u00e7as Corporativas e aprovado nos concursos de Auditor Fiscal SEFAZ-SC e SEFAZ-GO.","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/leandro_vzthotmail-com\/"}]}},"_links":{"self":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/509517","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/users\/1668"}],"replies":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/comments?post=509517"}],"version-history":[{"count":5,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/509517\/revisions"}],"predecessor-version":[{"id":510762,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/509517\/revisions\/510762"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media\/509521"}],"wp:attachment":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media?parent=509517"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/categories?post=509517"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tags?post=509517"},{"taxonomy":"tax_estado","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tax_estado?post=509517"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}