{"id":504813,"date":"2020-05-03T12:00:00","date_gmt":"2020-05-03T15:00:00","guid":{"rendered":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?p=504813"},"modified":"2023-06-28T14:09:27","modified_gmt":"2023-06-28T17:09:27","slug":"matematica-financeira-para-o-tce-sc-veja-5-dicas-de-como-se-preparar","status":"publish","type":"post","link":"https:\/\/www.estrategiaconcursos.com.br\/blog\/matematica-financeira-para-o-tce-sc-veja-5-dicas-de-como-se-preparar\/","title":{"rendered":"Matem\u00e1tica Financeira para o TCE SC. Veja 5 dicas de como se preparar"},"content":{"rendered":"\n<p class=\"has-medium-font-size\"><em>Est\u00e1 estudando para o Tribunal de Contas de Santa Catarina? Veja o que priorizar nos estudos de <strong>matem\u00e1tica financeira para o TCE SC<\/strong>.<\/em><\/p>\n\n\n\n<p>Ol\u00e1 pessoal, tudo bem? Eu espero que sim!<\/p>\n\n\n\n<p>Aguardamos ansiosos a publica\u00e7\u00e3o do edital do Tribunal de Contas de SC, que dever\u00e1 ocorrer j\u00e1 nos pr\u00f3ximos meses, com provas no final deste ano ou no in\u00edcio de 2021. Todavia, devemos nos antever ao que se esperar para o certame. Atitudes proativas como esta pode nos colocar um posso \u00e0 frente dos demais concorrentes.<\/p>\n\n\n\n<p>De acordo com o <a href=\"http:\/\/www.cespe.unb.br\/concursos\/TCE_SC_15\/arquivos\/TCE_SC_2015_ED_1___ABERTURA___CONFORME_DI__RIO.PDF\">\u00faltimo edital<\/a> (2015), <strong>matem\u00e1tica financeira para o TCE SC<\/strong> foi exigida na parte de <strong>conhecimentos espec\u00edficos<\/strong> para as seguintes especialidades: Administra\u00e7\u00e3o, Contabilidade e Economia. Portanto, \u00e9 esperada sua reincid\u00eancia no pr\u00f3ximo edital.<\/p>\n\n\n\n<p>Certamente que Matem\u00e1tica Financeira divide opini\u00f5es, uns amam enquanto outros odeiam. N\u00e3o se deve confundir, entretanto, <strong>matem\u00e1tica financeira<\/strong> com <strong>racioc\u00ednio l\u00f3gico<\/strong>. Enquanto a maior parte das quest\u00f5es de RLM trabalha com tabelas verdades e proposi\u00e7\u00f5es, e, geralmente, com poucas contas, por outro lado, matem\u00e1tica financeira baseia-se em f\u00f3rmulas, exigindo do candidato n\u00e3o s\u00f3 dom\u00ednio do conte\u00fado, como tamb\u00e9m agilidade nos c\u00e1lculos.<\/p>\n\n\n\n<p>Desse modo, o aluno deve se preparar muito bem para essa disciplina, uma vez que <strong>ela ir\u00e1 diferenciar os candidatos<\/strong>. Com esse objetivo, preparamos aqui 5 dicas de como se preparar para <strong>Matem\u00e1tica Financeira para o TCE SC<\/strong>.<\/p>\n\n\n\n<h1 class=\"wp-block-heading\" id=\"h-1-saiba-as-estatisticas-de-cobranca-de-matematica-financeira-para-o-tce-sc\">1)&nbsp;&nbsp;&nbsp; Saiba as Estat\u00edsticas de Cobran\u00e7a de Matem\u00e1tica Financeira para o TCE SC<\/h1>\n\n\n\n<p>Antes de tudo, precisamos entender as prefer\u00eancias das bancas sobre cada assunto. Como j\u00e1 sabemos que a banca organizadora ser\u00e1 a CESPE, isso facilitar\u00e1 nossa an\u00e1lise. Veja os dados abaixo.<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"340\" height=\"429\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/04\/17115135\/image-183.png\" alt=\"Matem\u00e1tica Financeira para o TCE SC\" class=\"wp-image-504816\" srcset=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/04\/17115135\/image-183.png 340w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/04\/17115135\/image-183-238x300.png 238w\" sizes=\"auto, (max-width: 340px) 100vw, 340px\" \/><figcaption class=\"wp-element-caption\">Estat\u00edstica de cobran\u00e7a Matem\u00e1tica Financeira CESPE<\/figcaption><\/figure>\n\n\n\n<p>A estat\u00edstica de cobran\u00e7a acima demonstra que 80% dos exerc\u00edcios cobrados est\u00e3o relacionados a:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Sistemas de Amortiza\u00e7\u00e3o;<\/li>\n\n\n\n<li>Juros Compostos;<\/li>\n\n\n\n<li>Taxas Equivalentes e Proporcionais (Regime composto);<\/li>\n\n\n\n<li>Juros Simples;<\/li>\n\n\n\n<li>Pagamentos Uniformes (s\u00e9rie de pagamentos);<\/li>\n\n\n\n<li>Infla\u00e7\u00e3o, Juros Reais e Juros Aparentes; e<\/li>\n\n\n\n<li>Desconto Simples (Racional e Comercial).<\/li>\n<\/ul>\n\n\n\n<p>Al\u00e9m disso, a banca tem ci\u00eancia de que, para assuntos que exigem grande n\u00famero de c\u00e1lculos, o tempo de prova n\u00e3o \u00e9 suficiente. Isto explica a baix\u00edssima cobran\u00e7a de alguns t\u00f3picos, como por exemplo: s\u00e9rie de pagamentos vari\u00e1veis. N\u00e3o obstante, sabendo as estat\u00edsticas de cobran\u00e7a, o candidato saber\u00e1 no que focar em maior escala.<\/p>\n\n\n\n<h1 class=\"wp-block-heading\" id=\"h-2-faca-exercicios-e-veja-a-resolucao-do-professor\">2)&nbsp;&nbsp;&nbsp; Fa\u00e7a exerc\u00edcios e veja a resolu\u00e7\u00e3o do professor<\/h1>\n\n\n\n<p>Como dito, em matem\u00e1tica financeira para o TCE SC, o tempo ser\u00e1 precioso. Portanto, o aluno precisar\u00e1 buscar m\u00e9todos de aprimorar seus c\u00e1lculos e suas resolu\u00e7\u00f5es.<\/p>\n\n\n\n<p>Como \u00e9 sabido, um exerc\u00edcio pode ser resolvido por <em>n<\/em> maneiras diferentes, e saber o m\u00e9todo mais r\u00e1pido e direto colocar\u00e1 o candidato em uma posi\u00e7\u00e3o de vantagem. Portanto, treine bastante, fa\u00e7a muitos exerc\u00edcios. Apenas a pr\u00e1tica ir\u00e1 ensin\u00e1-lo o melhor caminho. Al\u00e9m do mais, experi\u00eancia gera agilidade.<\/p>\n\n\n\n<p>Ademais, busque sempre verificar a resolu\u00e7\u00e3o do professor, por mais que tenha acertado o exerc\u00edcio. Muitas das vezes, poder\u00e1 aprender uma nova maneira de se pensar e agilizar sua resolu\u00e7\u00e3o.<\/p>\n\n\n\n<h1 class=\"wp-block-heading\" id=\"h-3-nao-se-case-com-uma-questao\">3)&nbsp;&nbsp;&nbsp; N\u00e3o se case com uma quest\u00e3o<\/h1>\n\n\n\n<p>Indo na mesma linha de racioc\u00ednio da dica anterior, devemos sempre nos preocupar com o tempo de resolu\u00e7\u00e3o. N\u00e3o s\u00f3 buscar resolver os exerc\u00edcios no menor tempo poss\u00edvel, como tamb\u00e9m saber o momento certo de deixar de lado e seguir em frente.<\/p>\n\n\n\n<p>\u00c9 bastante comum vermos relatos de alunos que passaram 10-15 minutos em uma mesma quest\u00e3o, na busca de conseguir resolv\u00ea-la. Todavia, esse tempo \u00e9 suficiente para que o candidato tenha solucionado outros 3 ou 4 exerc\u00edcios de outra disciplina. E no final, a queixa \u00e9 sempre a mesma: n\u00e3o deu tempo de terminar a prova. Portanto, n\u00e3o se case com uma quest\u00e3o. Se, ao ler e entender o enunciado, n\u00e3o souber o que fazer, pr\u00f3ximo exerc\u00edcio.<\/p>\n\n\n\n<p>Acredite, seu subconsciente estar\u00e1 trabalhando em alternativas de resolu\u00e7\u00e3o deste enunciado. Ao final da prova, quando retornar \u00e0quela quest\u00e3o, poder\u00e1 se surpreender.<\/p>\n\n\n\n<h1 class=\"wp-block-heading\" id=\"h-4-saiba-a-hora-certa-de-estudar-matematica-financeira-para-o-tce-sc\">4)&nbsp;&nbsp;&nbsp; Saiba a hora certa de estudar Matem\u00e1tica Financeira para o TCE SC<\/h1>\n\n\n\n<p>Para tudo nessa vida existe a hora certa, e para estudar n\u00e3o \u00e9 diferente. Enquanto alguns veem matem\u00e1tica financeira como um mart\u00edrio, outros veem como um momento de se relaxar, esvaziar a mente. Logo, precisamos saber o momento correto de estudar <strong>matem\u00e1tica financeira para o TCE SC<\/strong>.<\/p>\n\n\n\n<p>Para os que amam essa disciplina, busquem estud\u00e1-la em momentos de resist\u00eancia, em que o aluno precisar\u00e1 de uma motiva\u00e7\u00e3o extra, como nos finais de semana, sexta-feira \u00e0 noite, segunda-feira (a motiva\u00e7\u00e3o extra \u00e9 justamente estudar para aquilo que gosta).<\/p>\n\n\n\n<p>Por outro lado, aos que odeiam, tente focar nessa mat\u00e9ria nos dias do meio da semana e na parte da manh\u00e3, em que sua mente estar\u00e1 leve e propicia a realizar maiores esfor\u00e7os.<\/p>\n\n\n\n<h1 class=\"wp-block-heading\" id=\"h-5-entenda-bem-o-enunciado\">5)&nbsp;&nbsp;&nbsp; Entenda bem o enunciado<\/h1>\n\n\n\n<p>Por \u00faltimo, leia e entenda o enunciado quantas vezes forem necess\u00e1rias, antes de tentar resolver a quest\u00e3o. Parece banal, mas esse tipo de erro ainda \u00e9 comum.<\/p>\n\n\n\n<p>Matem\u00e1tica financeira \u00e9 uma disciplina com alto grau de \u201cpegadinhas\u201d, e as alternativas s\u00e3o cuidadosamente calculadas para coincidir com os c\u00e1lculos errados que os alunos eventualmente realizam durante a resolu\u00e7\u00e3o.<\/p>\n\n\n\n<p>Portanto, n\u00e3o saia fazendo contas antes de saber exatamente quais devem ser realizadas. Al\u00e9m de desperdi\u00e7ar tempo, correr\u00e1 grande risco de que seus c\u00e1lculos incorretos coincidam com uma das alternativas.<\/p>\n\n\n\n<p>Veja ainda esse <a href=\"https:\/\/www.youtube.com\/user\/EstrategiaCursos\/search?query=matem%C3%A1tica+financeira\">s\u00e9rie de v\u00eddeos<\/a> com teorias e resolu\u00e7\u00f5es de exerc\u00edcios sobre Matem\u00e1tica Financeira.<\/p>\n\n\n\n<p>Um forte abra\u00e7o<\/p>\n\n\n\n<p>Leandro Ricardo M. Silveira<\/p>\n\n\n\n<p><strong>Instagram: <\/strong><a href=\"https:\/\/www.instagram.com\/leandro.rms12\/\">https:\/\/www.instagram.com\/leandro.rms12\/<\/a><\/p>\n\n\n\n<p class=\"has-text-align-center has-medium-font-size\"><em><strong>Assinatura Anual Ilimitada*<\/strong><\/em><\/p>\n\n\n\n<p class=\"has-text-align-center\"><em>Prepare-se com o melhor material e com quem mais aprova em Concursos P\u00fablicos em todo o pa\u00eds. Assine agora a nossa Assinatura Anual e tenha acesso ilimitado* a todos os nossos cursos.<\/em><\/p>\n\n\n\n<p class=\"has-text-align-center has-luminous-vivid-amber-background-color has-background\" style=\"font-size:clamp(14.642px, 0.915rem + ((1vw - 3.2px) * 0.721), 22px);px\"><strong>ASSINE AGORA<\/strong>&nbsp;\u2013&nbsp;<a rel=\"noreferrer noopener\" href=\"https:\/\/www.estrategiaconcursos.com.br\/assinaturas\" target=\"_blank\"><strong>Assinatura Ilimitada<\/strong><\/a><\/p>\n\n\n\n<p class=\"has-text-align-center has-medium-font-size\"><em><strong>Fique por dentro de todos os concursos<\/strong><\/em>:<\/p>\n\n\n\n<p class=\"has-text-align-center has-pale-cyan-blue-background-color has-background\" style=\"font-size:clamp(14.642px, 0.915rem + ((1vw - 3.2px) * 0.721), 22px);px\"><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-abertos\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Concursos abertos<\/strong><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Est\u00e1 estudando para o Tribunal de Contas de Santa Catarina? Veja o que priorizar nos estudos de matem\u00e1tica financeira para o TCE SC. Ol\u00e1 pessoal, tudo bem? Eu espero que sim! Aguardamos ansiosos a publica\u00e7\u00e3o do edital do Tribunal de Contas de SC, que dever\u00e1 ocorrer j\u00e1 nos pr\u00f3ximos meses, com provas no final deste [&hellip;]<\/p>\n","protected":false},"author":1668,"featured_media":22134,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"post_tipo":"article","footnotes":""},"categories":[1,1984],"tags":[516,682],"tax_estado":[],"class_list":["post-504813","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cursos-e-concursos","category-tribunais","tag-matematica-financeira","tag-tce-sc"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.2 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Matem\u00e1tica Financeira para o TCE SC. Veja 5 dicas de como se preparar<\/title>\n<meta name=\"description\" content=\"Veja 5 dicas importantes para se preparar para Matem\u00e1tica Financeira para o TCE SC, juntamente com estat\u00edstica de cobran\u00e7a da CESPE.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/matematica-financeira-para-o-tce-sc-veja-5-dicas-de-como-se-preparar\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Matem\u00e1tica Financeira para o TCE SC. Veja 5 dicas de como se preparar\" \/>\n<meta property=\"og:description\" content=\"Veja 5 dicas importantes para se preparar para Matem\u00e1tica Financeira para o TCE SC, juntamente com estat\u00edstica de cobran\u00e7a da CESPE.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/matematica-financeira-para-o-tce-sc-veja-5-dicas-de-como-se-preparar\/\" \/>\n<meta property=\"og:site_name\" content=\"Estrat\u00e9gia Concursos\" \/>\n<meta property=\"article:published_time\" content=\"2020-05-03T15:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-06-28T17:09:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2015\/03\/concurso-TCE-SC.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"140\" \/>\n\t<meta property=\"og:image:height\" content=\"205\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Leandro Ricardo Machado da Silveira\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:site\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Leandro Ricardo Machado da Silveira\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/matematica-financeira-para-o-tce-sc-veja-5-dicas-de-como-se-preparar\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/matematica-financeira-para-o-tce-sc-veja-5-dicas-de-como-se-preparar\/\"},\"author\":{\"name\":\"Leandro Ricardo Machado da Silveira\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/c666a44fbce7e2e70009a9c13549267a\"},\"headline\":\"Matem\u00e1tica Financeira para o TCE SC. Veja 5 dicas de como se preparar\",\"datePublished\":\"2020-05-03T15:00:00+00:00\",\"dateModified\":\"2023-06-28T17:09:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/matematica-financeira-para-o-tce-sc-veja-5-dicas-de-como-se-preparar\/\"},\"wordCount\":1058,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/matematica-financeira-para-o-tce-sc-veja-5-dicas-de-como-se-preparar\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2015\/03\/concurso-TCE-SC.jpg\",\"keywords\":[\"Matem\u00e1tica Financeira\",\"TCE-SC\"],\"articleSection\":[\"Concursos P\u00fablicos\",\"Tribunais\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/matematica-financeira-para-o-tce-sc-veja-5-dicas-de-como-se-preparar\/#respond\"]}],\"copyrightYear\":\"2020\",\"copyrightHolder\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/matematica-financeira-para-o-tce-sc-veja-5-dicas-de-como-se-preparar\/\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/matematica-financeira-para-o-tce-sc-veja-5-dicas-de-como-se-preparar\/\",\"name\":\"Matem\u00e1tica Financeira para o TCE SC. Veja 5 dicas de como se preparar\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/matematica-financeira-para-o-tce-sc-veja-5-dicas-de-como-se-preparar\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/matematica-financeira-para-o-tce-sc-veja-5-dicas-de-como-se-preparar\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2015\/03\/concurso-TCE-SC.jpg\",\"datePublished\":\"2020-05-03T15:00:00+00:00\",\"dateModified\":\"2023-06-28T17:09:27+00:00\",\"description\":\"Veja 5 dicas importantes para se preparar para Matem\u00e1tica Financeira para o TCE SC, juntamente com estat\u00edstica de cobran\u00e7a da CESPE.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/matematica-financeira-para-o-tce-sc-veja-5-dicas-de-como-se-preparar\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/matematica-financeira-para-o-tce-sc-veja-5-dicas-de-como-se-preparar\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/matematica-financeira-para-o-tce-sc-veja-5-dicas-de-como-se-preparar\/#primaryimage\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2015\/03\/concurso-TCE-SC.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2015\/03\/concurso-TCE-SC.jpg\",\"width\":140,\"height\":205},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/matematica-financeira-para-o-tce-sc-veja-5-dicas-de-como-se-preparar\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Matem\u00e1tica Financeira para o TCE SC. Veja 5 dicas de como se preparar\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"name\":\"Estrat\u00e9gia Concursos\",\"description\":\"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.\",\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\",\"name\":\"Estrat\u00e9gia Concursos\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"width\":230,\"height\":60,\"caption\":\"Estrat\u00e9gia Concursos\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/EstratConcursos\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/c666a44fbce7e2e70009a9c13549267a\",\"name\":\"Leandro Ricardo Machado da Silveira\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/6fb25994d16b9649838400aa459b16c1c83f558e0fd6ebebd16da0473908b291?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/6fb25994d16b9649838400aa459b16c1c83f558e0fd6ebebd16da0473908b291?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/6fb25994d16b9649838400aa459b16c1c83f558e0fd6ebebd16da0473908b291?s=96&d=mm&r=g\",\"caption\":\"Leandro Ricardo Machado da Silveira\"},\"description\":\"Engenheiro Aeron\u00e1utico, formado pela Universidade Federal de Uberl\u00e2ndia, possui MBA em Administra\u00e7\u00e3o e Finan\u00e7as Corporativas e aprovado nos concursos de Auditor Fiscal SEFAZ-SC e SEFAZ-GO.\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/leandro_vzthotmail-com\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Matem\u00e1tica Financeira para o TCE SC. Veja 5 dicas de como se preparar","description":"Veja 5 dicas importantes para se preparar para Matem\u00e1tica Financeira para o TCE SC, juntamente com estat\u00edstica de cobran\u00e7a da CESPE.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.estrategiaconcursos.com.br\/blog\/matematica-financeira-para-o-tce-sc-veja-5-dicas-de-como-se-preparar\/","og_locale":"pt_BR","og_type":"article","og_title":"Matem\u00e1tica Financeira para o TCE SC. Veja 5 dicas de como se preparar","og_description":"Veja 5 dicas importantes para se preparar para Matem\u00e1tica Financeira para o TCE SC, juntamente com estat\u00edstica de cobran\u00e7a da CESPE.","og_url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/matematica-financeira-para-o-tce-sc-veja-5-dicas-de-como-se-preparar\/","og_site_name":"Estrat\u00e9gia Concursos","article_published_time":"2020-05-03T15:00:00+00:00","article_modified_time":"2023-06-28T17:09:27+00:00","og_image":[{"width":140,"height":205,"url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2015\/03\/concurso-TCE-SC.jpg","type":"image\/jpeg"}],"author":"Leandro Ricardo Machado da Silveira","twitter_card":"summary_large_image","twitter_creator":"@EstratConcursos","twitter_site":"@EstratConcursos","twitter_misc":{"Escrito por":"Leandro Ricardo Machado da Silveira","Est. tempo de leitura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/matematica-financeira-para-o-tce-sc-veja-5-dicas-de-como-se-preparar\/#article","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/matematica-financeira-para-o-tce-sc-veja-5-dicas-de-como-se-preparar\/"},"author":{"name":"Leandro Ricardo Machado da Silveira","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/c666a44fbce7e2e70009a9c13549267a"},"headline":"Matem\u00e1tica Financeira para o TCE SC. Veja 5 dicas de como se preparar","datePublished":"2020-05-03T15:00:00+00:00","dateModified":"2023-06-28T17:09:27+00:00","mainEntityOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/matematica-financeira-para-o-tce-sc-veja-5-dicas-de-como-se-preparar\/"},"wordCount":1058,"commentCount":0,"publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/matematica-financeira-para-o-tce-sc-veja-5-dicas-de-como-se-preparar\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2015\/03\/concurso-TCE-SC.jpg","keywords":["Matem\u00e1tica Financeira","TCE-SC"],"articleSection":["Concursos P\u00fablicos","Tribunais"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/matematica-financeira-para-o-tce-sc-veja-5-dicas-de-como-se-preparar\/#respond"]}],"copyrightYear":"2020","copyrightHolder":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/matematica-financeira-para-o-tce-sc-veja-5-dicas-de-como-se-preparar\/","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/matematica-financeira-para-o-tce-sc-veja-5-dicas-de-como-se-preparar\/","name":"Matem\u00e1tica Financeira para o TCE SC. Veja 5 dicas de como se preparar","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/matematica-financeira-para-o-tce-sc-veja-5-dicas-de-como-se-preparar\/#primaryimage"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/matematica-financeira-para-o-tce-sc-veja-5-dicas-de-como-se-preparar\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2015\/03\/concurso-TCE-SC.jpg","datePublished":"2020-05-03T15:00:00+00:00","dateModified":"2023-06-28T17:09:27+00:00","description":"Veja 5 dicas importantes para se preparar para Matem\u00e1tica Financeira para o TCE SC, juntamente com estat\u00edstica de cobran\u00e7a da CESPE.","breadcrumb":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/matematica-financeira-para-o-tce-sc-veja-5-dicas-de-como-se-preparar\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/matematica-financeira-para-o-tce-sc-veja-5-dicas-de-como-se-preparar\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/matematica-financeira-para-o-tce-sc-veja-5-dicas-de-como-se-preparar\/#primaryimage","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2015\/03\/concurso-TCE-SC.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2015\/03\/concurso-TCE-SC.jpg","width":140,"height":205},{"@type":"BreadcrumbList","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/matematica-financeira-para-o-tce-sc-veja-5-dicas-de-como-se-preparar\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.estrategiaconcursos.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Matem\u00e1tica Financeira para o TCE SC. Veja 5 dicas de como se preparar"}]},{"@type":"WebSite","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","name":"Estrat\u00e9gia Concursos","description":"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.","publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization","name":"Estrat\u00e9gia Concursos","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","width":230,"height":60,"caption":"Estrat\u00e9gia Concursos"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/EstratConcursos"]},{"@type":"Person","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/c666a44fbce7e2e70009a9c13549267a","name":"Leandro Ricardo Machado da Silveira","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/6fb25994d16b9649838400aa459b16c1c83f558e0fd6ebebd16da0473908b291?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/6fb25994d16b9649838400aa459b16c1c83f558e0fd6ebebd16da0473908b291?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6fb25994d16b9649838400aa459b16c1c83f558e0fd6ebebd16da0473908b291?s=96&d=mm&r=g","caption":"Leandro Ricardo Machado da Silveira"},"description":"Engenheiro Aeron\u00e1utico, formado pela Universidade Federal de Uberl\u00e2ndia, possui MBA em Administra\u00e7\u00e3o e Finan\u00e7as Corporativas e aprovado nos concursos de Auditor Fiscal SEFAZ-SC e SEFAZ-GO.","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/leandro_vzthotmail-com\/"}]}},"_links":{"self":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/504813","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/users\/1668"}],"replies":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/comments?post=504813"}],"version-history":[{"count":10,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/504813\/revisions"}],"predecessor-version":[{"id":1240314,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/504813\/revisions\/1240314"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media\/22134"}],"wp:attachment":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media?parent=504813"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/categories?post=504813"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tags?post=504813"},{"taxonomy":"tax_estado","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tax_estado?post=504813"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}