{"id":499708,"date":"2020-04-03T11:33:13","date_gmt":"2020-04-03T14:33:13","guid":{"rendered":"https:\/\/blog-estrategia.mystagingwebsite.com\/blog\/?p=499708"},"modified":"2020-04-03T18:29:50","modified_gmt":"2020-04-03T21:29:50","slug":"pl-que-suspende-validade-dos-concursos-rj-e-aprovada","status":"publish","type":"post","link":"https:\/\/www.estrategiaconcursos.com.br\/blog\/pl-que-suspende-validade-dos-concursos-rj-e-aprovada\/","title":{"rendered":"PL que suspende validade dos concursos RJ \u00e9 aprovada pela CCJ"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">A Comiss\u00e3o de Constitui\u00e7\u00e3o e Justi\u00e7a (CCJ) aprovou o Projeto de Lei N\u00ba 2202\/2020, que visa suspender os prazos de validade dos concursos p\u00fablicos j\u00e1 homologados, durante o per\u00edodo do surto da COVID-19.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A proposta, apresentada pelo deputado Renato Cozzolino, visa suspender a validade dos concursos da administra\u00e7\u00e3o direta e indireta (executivo, legislativo, judici\u00e1rio, autarquias, MP\u2026) no estado do Rio de Janeiro, uma vez que muitas atividades p\u00fablicas e privadas est\u00e3o suspensas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dessa forma, a CCJ aprovou a legalidade do Projeto de Lei, em reuni\u00e3o realizada na \u00faltima quinta-feira, 02 de abril. Agora, o PL ser\u00e1 avaliado pelas Comiss\u00f5es Permanentes ligadas ao tema.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Diferente de outras avalia\u00e7\u00f5es, o Projeto dever\u00e1 ser analisado em cerca de tr\u00eas dias, uma vez que corre em car\u00e1ter de urg\u00eancia.<\/p>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\"><em>Confira o Parecer publicado no caderno Legislativo do Di\u00e1rio Oficial do RJ nesta sexta-feira, 04 de abril:<\/em><\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"467\" height=\"795\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/04\/03111356\/rj.png\" alt=\"\" class=\"wp-image-499715\" srcset=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/04\/03111356\/rj.png 467w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/04\/03111356\/rj-176x300.png 176w\" sizes=\"auto, (max-width: 467px) 100vw, 467px\" \/><\/figure><\/div>\n\n\n\n<p class=\"has-background has-text-align-center has-medium-font-size has-very-light-gray-background-color wp-block-paragraph\"><strong><a rel=\"noreferrer noopener\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/coronavirus-provas-adiadas-2020\/\" target=\"_blank\">Concursos suspensos e provas adiadas<\/a><\/strong><\/p>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\"><em><strong>Assinatura Anual Ilimitada*<\/strong><\/em><\/p>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\"><em>Prepare-se com o melhor material e com quem mais aprova em Concursos P\u00fablicos em todo o pa\u00eds. Assine agora a nossa Assinatura Anual e tenha acesso ilimitado* a todos os nossos cursos.<\/em><\/p>\n\n\n\n<p class=\"has-background has-text-align-center has-medium-font-size has-light-green-cyan-background-color wp-block-paragraph\"><strong>ASSINE AGORA&nbsp;\u2013&nbsp;<\/strong><a rel=\"noreferrer noopener\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/assinaturas\" target=\"_blank\"><strong>Assinatura Ilimitada<\/strong><\/a><\/p>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\"><strong><em>Fique por dentro de todos os concursos<\/em><\/strong><\/p>\n\n\n\n<p class=\"has-background has-text-align-center has-medium-font-size has-pale-cyan-blue-background-color wp-block-paragraph\"><strong><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-rj-2\/\" target=\"_blank\" rel=\"noreferrer noopener\">Concursos RJ<\/a><\/strong><\/p>\n\n\n\n<p class=\"has-background has-text-align-center has-medium-font-size has-pale-cyan-blue-background-color wp-block-paragraph\"><a rel=\"noreferrer noopener\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-abertos\/\" target=\"_blank\"><strong>Concursos Abertos<\/strong><\/a><\/p>\n\n\n\n<p class=\"has-background has-text-align-center has-medium-font-size has-pale-cyan-blue-background-color wp-block-paragraph\"><a rel=\"noreferrer noopener\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-2020\/\" target=\"_blank\"><strong>Concursos 2020<\/strong><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Comiss\u00e3o de Constitui\u00e7\u00e3o e Justi\u00e7a (CCJ) aprovou o Projeto de Lei N\u00ba 2202\/2020, que visa suspender os prazos de validade dos concursos p\u00fablicos j\u00e1 homologados, durante o per\u00edodo do surto da COVID-19. A proposta, apresentada pelo deputado Renato Cozzolino, visa suspender a validade dos concursos da administra\u00e7\u00e3o direta e indireta (executivo, legislativo, judici\u00e1rio, autarquias, [&hellip;]<\/p>\n","protected":false},"author":741,"featured_media":76777,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"post_tipo":"article","footnotes":""},"categories":[1],"tags":[],"tax_estado":[],"class_list":["post-499708","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cursos-e-concursos"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.1 (Yoast SEO v28.1) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>PL que suspende validade dos concursos RJ \u00e9 aprovada pela CCJ<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/pl-que-suspende-validade-dos-concursos-rj-e-aprovada\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"PL que suspende validade dos concursos RJ \u00e9 aprovada pela CCJ\" \/>\n<meta property=\"og:description\" content=\"A Comiss\u00e3o de Constitui\u00e7\u00e3o e Justi\u00e7a (CCJ) aprovou o Projeto de Lei N\u00ba 2202\/2020, que visa suspender os prazos de validade dos concursos p\u00fablicos j\u00e1 homologados, durante o per\u00edodo do surto da COVID-19. A proposta, apresentada pelo deputado Renato Cozzolino, visa suspender a validade dos concursos da administra\u00e7\u00e3o direta e indireta (executivo, legislativo, judici\u00e1rio, autarquias, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/pl-que-suspende-validade-dos-concursos-rj-e-aprovada\/\" \/>\n<meta property=\"og:site_name\" content=\"Estrat\u00e9gia Concursos\" \/>\n<meta property=\"article:published_time\" content=\"2020-04-03T14:33:13+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-04-03T21:29:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2017\/06\/07135854\/CONC-RJ-e1496854747249.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"400\" \/>\n\t<meta property=\"og:image:height\" content=\"209\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Brunno Lima\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:site\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Brunno Lima\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/pl-que-suspende-validade-dos-concursos-rj-e-aprovada\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/pl-que-suspende-validade-dos-concursos-rj-e-aprovada\\\/\"},\"author\":{\"name\":\"Brunno Lima\",\"@id\":\"https:\\\/\\\/blog-estrategia.mystagingwebsite.com\\\/#\\\/schema\\\/person\\\/2865ec132c3404c9912015dd7a24eb1e\"},\"headline\":\"PL que suspende validade dos concursos RJ \u00e9 aprovada pela CCJ\",\"datePublished\":\"2020-04-03T14:33:13+00:00\",\"dateModified\":\"2020-04-03T21:29:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/pl-que-suspende-validade-dos-concursos-rj-e-aprovada\\\/\"},\"wordCount\":225,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/blog-estrategia.mystagingwebsite.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/pl-que-suspende-validade-dos-concursos-rj-e-aprovada\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dhg1h5j42swfq.cloudfront.net\\\/2017\\\/06\\\/07135854\\\/CONC-RJ-e1496854747249.jpg\",\"articleSection\":[\"Concursos P\u00fablicos\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/pl-que-suspende-validade-dos-concursos-rj-e-aprovada\\\/#respond\"]}],\"copyrightYear\":\"2020\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/pl-que-suspende-validade-dos-concursos-rj-e-aprovada\\\/\",\"url\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/pl-que-suspende-validade-dos-concursos-rj-e-aprovada\\\/\",\"name\":\"PL que suspende validade dos concursos RJ \u00e9 aprovada pela CCJ\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog-estrategia.mystagingwebsite.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/pl-que-suspende-validade-dos-concursos-rj-e-aprovada\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/pl-que-suspende-validade-dos-concursos-rj-e-aprovada\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dhg1h5j42swfq.cloudfront.net\\\/2017\\\/06\\\/07135854\\\/CONC-RJ-e1496854747249.jpg\",\"datePublished\":\"2020-04-03T14:33:13+00:00\",\"dateModified\":\"2020-04-03T21:29:50+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/pl-que-suspende-validade-dos-concursos-rj-e-aprovada\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/pl-que-suspende-validade-dos-concursos-rj-e-aprovada\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/pl-que-suspende-validade-dos-concursos-rj-e-aprovada\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dhg1h5j42swfq.cloudfront.net\\\/2017\\\/06\\\/07135854\\\/CONC-RJ-e1496854747249.jpg\",\"contentUrl\":\"https:\\\/\\\/dhg1h5j42swfq.cloudfront.net\\\/2017\\\/06\\\/07135854\\\/CONC-RJ-e1496854747249.jpg\",\"width\":400,\"height\":209,\"caption\":\"SMS RJ\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/pl-que-suspende-validade-dos-concursos-rj-e-aprovada\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/blog-estrategia.mystagingwebsite.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"PL que suspende validade dos concursos RJ \u00e9 aprovada pela CCJ\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blog-estrategia.mystagingwebsite.com\\\/#website\",\"url\":\"https:\\\/\\\/blog-estrategia.mystagingwebsite.com\\\/\",\"name\":\"Estrat\u00e9gia Concursos\",\"description\":\"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.\",\"publisher\":{\"@id\":\"https:\\\/\\\/blog-estrategia.mystagingwebsite.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blog-estrategia.mystagingwebsite.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/blog-estrategia.mystagingwebsite.com\\\/#organization\",\"name\":\"Estrat\u00e9gia Concursos\",\"url\":\"https:\\\/\\\/blog-estrategia.mystagingwebsite.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/blog-estrategia.mystagingwebsite.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dhg1h5j42swfq.cloudfront.net\\\/2025\\\/06\\\/03203428\\\/logo_concursos-1.jpg\",\"contentUrl\":\"https:\\\/\\\/dhg1h5j42swfq.cloudfront.net\\\/2025\\\/06\\\/03203428\\\/logo_concursos-1.jpg\",\"width\":230,\"height\":60,\"caption\":\"Estrat\u00e9gia Concursos\"},\"image\":{\"@id\":\"https:\\\/\\\/blog-estrategia.mystagingwebsite.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/EstratConcursos\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/blog-estrategia.mystagingwebsite.com\\\/#\\\/schema\\\/person\\\/2865ec132c3404c9912015dd7a24eb1e\",\"name\":\"Brunno Lima\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d40b472e5e2856222d4a4a1c3ee2189ed7d7a9f67dc3343b880cc1889a7bd6af?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d40b472e5e2856222d4a4a1c3ee2189ed7d7a9f67dc3343b880cc1889a7bd6af?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d40b472e5e2856222d4a4a1c3ee2189ed7d7a9f67dc3343b880cc1889a7bd6af?s=96&d=mm&r=g\",\"caption\":\"Brunno Lima\"},\"url\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/author\\\/brunnoestrategiaconcursos-com-br\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"PL que suspende validade dos concursos RJ \u00e9 aprovada pela CCJ","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.estrategiaconcursos.com.br\/blog\/pl-que-suspende-validade-dos-concursos-rj-e-aprovada\/","og_locale":"pt_BR","og_type":"article","og_title":"PL que suspende validade dos concursos RJ \u00e9 aprovada pela CCJ","og_description":"A Comiss\u00e3o de Constitui\u00e7\u00e3o e Justi\u00e7a (CCJ) aprovou o Projeto de Lei N\u00ba 2202\/2020, que visa suspender os prazos de validade dos concursos p\u00fablicos j\u00e1 homologados, durante o per\u00edodo do surto da COVID-19. A proposta, apresentada pelo deputado Renato Cozzolino, visa suspender a validade dos concursos da administra\u00e7\u00e3o direta e indireta (executivo, legislativo, judici\u00e1rio, autarquias, [&hellip;]","og_url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/pl-que-suspende-validade-dos-concursos-rj-e-aprovada\/","og_site_name":"Estrat\u00e9gia Concursos","article_published_time":"2020-04-03T14:33:13+00:00","article_modified_time":"2020-04-03T21:29:50+00:00","og_image":[{"width":400,"height":209,"url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2017\/06\/07135854\/CONC-RJ-e1496854747249.jpg","type":"image\/jpeg"}],"author":"Brunno Lima","twitter_card":"summary_large_image","twitter_creator":"@EstratConcursos","twitter_site":"@EstratConcursos","twitter_misc":{"Escrito por":"Brunno Lima","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/pl-que-suspende-validade-dos-concursos-rj-e-aprovada\/#article","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/pl-que-suspende-validade-dos-concursos-rj-e-aprovada\/"},"author":{"name":"Brunno Lima","@id":"https:\/\/blog-estrategia.mystagingwebsite.com\/#\/schema\/person\/2865ec132c3404c9912015dd7a24eb1e"},"headline":"PL que suspende validade dos concursos RJ \u00e9 aprovada pela CCJ","datePublished":"2020-04-03T14:33:13+00:00","dateModified":"2020-04-03T21:29:50+00:00","mainEntityOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/pl-que-suspende-validade-dos-concursos-rj-e-aprovada\/"},"wordCount":225,"commentCount":0,"publisher":{"@id":"https:\/\/blog-estrategia.mystagingwebsite.com\/#organization"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/pl-que-suspende-validade-dos-concursos-rj-e-aprovada\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2017\/06\/07135854\/CONC-RJ-e1496854747249.jpg","articleSection":["Concursos P\u00fablicos"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/pl-que-suspende-validade-dos-concursos-rj-e-aprovada\/#respond"]}],"copyrightYear":"2020","copyrightHolder":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/pl-que-suspende-validade-dos-concursos-rj-e-aprovada\/","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/pl-que-suspende-validade-dos-concursos-rj-e-aprovada\/","name":"PL que suspende validade dos concursos RJ \u00e9 aprovada pela CCJ","isPartOf":{"@id":"https:\/\/blog-estrategia.mystagingwebsite.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/pl-que-suspende-validade-dos-concursos-rj-e-aprovada\/#primaryimage"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/pl-que-suspende-validade-dos-concursos-rj-e-aprovada\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2017\/06\/07135854\/CONC-RJ-e1496854747249.jpg","datePublished":"2020-04-03T14:33:13+00:00","dateModified":"2020-04-03T21:29:50+00:00","breadcrumb":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/pl-que-suspende-validade-dos-concursos-rj-e-aprovada\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/pl-que-suspende-validade-dos-concursos-rj-e-aprovada\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/pl-que-suspende-validade-dos-concursos-rj-e-aprovada\/#primaryimage","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2017\/06\/07135854\/CONC-RJ-e1496854747249.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2017\/06\/07135854\/CONC-RJ-e1496854747249.jpg","width":400,"height":209,"caption":"SMS RJ"},{"@type":"BreadcrumbList","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/pl-que-suspende-validade-dos-concursos-rj-e-aprovada\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/blog-estrategia.mystagingwebsite.com\/"},{"@type":"ListItem","position":2,"name":"PL que suspende validade dos concursos RJ \u00e9 aprovada pela CCJ"}]},{"@type":"WebSite","@id":"https:\/\/blog-estrategia.mystagingwebsite.com\/#website","url":"https:\/\/blog-estrategia.mystagingwebsite.com\/","name":"Estrat\u00e9gia Concursos","description":"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.","publisher":{"@id":"https:\/\/blog-estrategia.mystagingwebsite.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blog-estrategia.mystagingwebsite.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/blog-estrategia.mystagingwebsite.com\/#organization","name":"Estrat\u00e9gia Concursos","url":"https:\/\/blog-estrategia.mystagingwebsite.com\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/blog-estrategia.mystagingwebsite.com\/#\/schema\/logo\/image\/","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","width":230,"height":60,"caption":"Estrat\u00e9gia Concursos"},"image":{"@id":"https:\/\/blog-estrategia.mystagingwebsite.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/EstratConcursos"]},{"@type":"Person","@id":"https:\/\/blog-estrategia.mystagingwebsite.com\/#\/schema\/person\/2865ec132c3404c9912015dd7a24eb1e","name":"Brunno Lima","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/d40b472e5e2856222d4a4a1c3ee2189ed7d7a9f67dc3343b880cc1889a7bd6af?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/d40b472e5e2856222d4a4a1c3ee2189ed7d7a9f67dc3343b880cc1889a7bd6af?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d40b472e5e2856222d4a4a1c3ee2189ed7d7a9f67dc3343b880cc1889a7bd6af?s=96&d=mm&r=g","caption":"Brunno Lima"},"url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/brunnoestrategiaconcursos-com-br\/"}]}},"_links":{"self":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/499708","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/users\/741"}],"replies":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/comments?post=499708"}],"version-history":[{"count":0,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/499708\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media\/76777"}],"wp:attachment":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media?parent=499708"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/categories?post=499708"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tags?post=499708"},{"taxonomy":"tax_estado","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tax_estado?post=499708"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}