{"id":48299,"date":"2020-01-04T11:30:00","date_gmt":"2020-01-04T14:30:00","guid":{"rendered":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?p=48299"},"modified":"2023-04-14T11:12:38","modified_gmt":"2023-04-14T14:12:38","slug":"resumos-em-audio","status":"publish","type":"post","link":"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumos-em-audio\/","title":{"rendered":"Resumos em \u00c1udio: passo a passo!"},"content":{"rendered":"\n<div class=\"wp-block-group is-layout-flow wp-block-group-is-layout-flow\">\n<h2 style=\"text-align: justify;\"><span style=\"color: #0000ff;\">Resumos em \u00c1udio<\/span><\/h2>\n<p style=\"text-align: justify;\"><span style=\"font-size: 12pt;\"><span style=\"font-family: georgia, palatino, serif;\">Eles economizam tempo, s\u00e3o f\u00e1ceis de serem constru\u00eddos e permitem o estudo em qualquer lugar, a qualquer momento!<br \/>Esses s\u00e3o os Resumos em \u00c1udio! Vamos falar um pouco sobre isso?! <\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 12pt;\"><span style=\"font-family: georgia, palatino, serif;\">Eu gostaria de contar para voc\u00ea como essa T\u00e9cnica de Estudo me ajudou a <strong>ganhar confian\u00e7a<\/strong> e ficar bom em disciplinas que eu tinha, inicialmente, grande dificuldade!\u00a0<\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 12pt;\"><span style=\"font-family: georgia, palatino, serif;\">Ah, s\u00f3 me apresentando! Eu me chamo\u00a0<strong>Luis Eduardo<\/strong>\u00a0e, novamente, estou dando sequ\u00eancia aos artigos sobre <strong>T\u00e9cnicas de Estudo<\/strong>.<br \/><\/span><\/span><span style=\"font-size: 12pt;\"><span style=\"font-family: georgia, palatino, serif;\">Para quem n\u00e3o me conhece, sou Auditor Fiscal do Estado de S\u00e3o Paulo e <em><strong>coach\u00a0<\/strong><\/em>aqui no Estrat\u00e9gia Concursos.<\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 12pt;\"><span style=\"font-family: georgia, palatino, serif;\">Voltando ao tema&#8230; caso voc\u00ea ainda n\u00e3o tenha lido os <strong>2 (dois) artigos anteriores<\/strong> sobre T\u00e9cnicas de Estudo, seria interessante que voc\u00ea fizesse isso antes de aprender esta t\u00e9cnica de hoje.<\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 12pt;\"><span style=\"font-family: georgia, palatino, serif;\">Digo isso pois, para fazer excelentes <strong>Resumos em \u00c1udio<\/strong>, \u00e9 imprescind\u00edvel que antes voc\u00ea tenha utilizado a t\u00e9cnica das &#8220;Marca\u00e7\u00f5es Preliminares&#8221; (MP&#8217;s) no material\/livro\/pdf com base no qual voc\u00ea pretende fazer os \u00e1udios, beleza?<\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 12pt;\"><span style=\"font-family: georgia, palatino, serif;\">Seguem os links para os artigos anteriores:<\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 12pt;\"><span style=\"font-family: georgia, palatino, serif;\"><span style=\"color: #ff0000;\"><span style=\"text-decoration: underline;\"><strong><span style=\"color: #0000ff; text-decoration: underline;\">Marca\u00e7\u00f5es Preliminares<\/span> (T\u00e9cnica de Estudo #1)<\/strong><\/span>:\u00a0<\/span><br \/><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/tecnicas-de-estudo-1-marcacoes-preliminares\/\">https:\/\/www.estrategiaconcursos.com.br\/blog\/tecnicas-de-estudo-1-marcacoes-preliminares\/<\/a><\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 12pt;\"><span style=\"font-family: georgia, palatino, serif;\"><span style=\"color: #ff0000;\"><span style=\"text-decoration: underline;\"><strong><span style=\"color: #0000ff; text-decoration: underline;\">Grifos e Anota\u00e7\u00f5es<\/span> (T\u00e9cnicas de Estudo #2)<\/strong><\/span>:<\/span><br \/><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/tecnicas-de-estudo-2-alternativa-aos-resumos-escritos-apresentacao-canal-do-youtube\/\">https:\/\/www.estrategiaconcursos.com.br\/blog\/tecnicas-de-estudo-2-alternativa-aos-resumos-escritos-apresentacao-canal-do-youtube\/<\/a><\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 12pt;\"><span style=\"font-family: georgia, palatino, serif;\">Agora sim, vamos aos Resumos em \u00c1udio&#8230;<\/span><\/span><\/p>\n<div id=\"attachment_48313\" style=\"width: 660px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2016\/09\/05225852\/ursinho-ouvindo-musica-3321.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-48313\" class=\"wp-image-48313\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2016\/09\/05225852\/ursinho-ouvindo-musica-3321.jpg\" alt=\"#Partiu resumos em \u00e1udio!\" width=\"650\" height=\"488\" srcset=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2016\/09\/05225852\/ursinho-ouvindo-musica-3321.jpg 1600w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2016\/09\/05225852\/ursinho-ouvindo-musica-3321.jpg 300w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2016\/09\/05225852\/ursinho-ouvindo-musica-3321.jpg 768w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2016\/09\/05225852\/ursinho-ouvindo-musica-3321.jpg 1024w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2016\/09\/05225852\/ursinho-ouvindo-musica-3321.jpg 400w\" sizes=\"auto, (max-width: 650px) 100vw, 650px\" \/><\/a><p id=\"caption-attachment-48313\" class=\"wp-caption-text\"><span style=\"font-size: 12pt;\"><span style=\"font-family: georgia, palatino, serif;\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<em>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0&#8220;Partiu resumos em \u00e1udio!&#8221;, disse TED.<\/em><\/span><\/span><\/p><\/div>\n<h2 style=\"text-align: justify;\"><span style=\"color: #0000ff;\">Vantagens<\/span><\/h2>\n<p style=\"text-align: justify;\"><span style=\"color: #0000ff;\"><em><span style=\"font-size: 12pt;\"><span style=\"font-family: georgia, palatino, serif;\">\u00a0<\/span><\/span><span style=\"font-size: 12pt;\"><span style=\"font-family: georgia, palatino, serif;\">1) O uso da audi\u00e7\u00e3o ajuda no processo de memoriza\u00e7\u00e3o!<\/span><\/span><\/em><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 12pt;\"><span style=\"font-family: georgia, palatino, serif;\">V\u00e1rios estudos j\u00e1 comprovaram que o est\u00edmulo a diferentes sentidos, ao inv\u00e9s de um \u00fanico, favorece a aprendizagem e memoriza\u00e7\u00e3o. H\u00e1 bastante coisa interessante &#8211; em ingl\u00eas &#8211; no site a seguir sobre o tema: <a href=\"http:\/\/www.educ.cam.ac.uk\/neuroscience\">www.educ.cam.ac.uk\/neuroscience<\/a>\u00a0(entretanto, n\u00e3o recomendo que percam tempo lendo sobre isso).<\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 12pt; color: #0000ff;\"><em><span style=\"font-family: georgia, palatino, serif;\">2) S\u00e3o r\u00e1pidos de serem feitos!<\/span><\/em><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 12pt;\"><span style=\"font-family: georgia, palatino, serif;\">Principalmente se comparados aos resumos escritos, os Resumos em \u00c1udio v\u00e3o tomar bem menos tempo da sua rotina. Geralmente, <strong>um \u00e1udio de 5 minutos demora cerca de 6 minutos e meio a 7 minutos para ser feito<\/strong>. Claro que, para que o seu resumo em \u00e1udio seja objetivo e traga apenas coisas importantes, <strong><span style=\"color: #ff0000;\">voc\u00ea precisa ter um m\u00e9todo ao faz\u00ea-lo<\/span><\/strong>. Neste artigo, eu vou sugerir uma forma eficiente para isso.<\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 12pt; color: #0000ff;\"><em><span style=\"font-family: georgia, palatino, serif;\">3) N\u00e3o precisam de qualquer investimento em canetas coloridas caras ou fichas, flashcards etc!<\/span><\/em><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 12pt;\"><span style=\"font-family: georgia, palatino, serif;\">Para fazer um resumo em \u00e1udio, voc\u00ea s\u00f3 precisa de um celular com algum aplicativo gravador de voz. Geralmente, todos os <i>smartphones<\/i> de hoje j\u00e1 trazem um gravador de voz instalado de f\u00e1brica.<\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 12pt; color: #0000ff;\"><em><span style=\"font-family: georgia, palatino, serif;\">4) F\u00e1cil de armazenar!<\/span><\/em><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 12pt;\"><span style=\"font-family: georgia, palatino, serif;\">Qualquer celular com mem\u00f3ria de 16 Gb consegue armazenar mais de 150h de \u00e1udio gravado em boa qualidade. Isso d\u00e1 resumo para mais de 70 disciplinas. rs! Voc\u00ea tamb\u00e9m pode\u00a0salvar os \u00e1udios na nuvem (Google Drive, Onedrive, Dropbox etc) e ter acesso a eles em qualquer lugar atrav\u00e9s da internet. Outra coisa importante&#8230; caso voc\u00ea tenha um <i>backup<\/i> dos seus resumos em \u00e1udios, ent\u00e3o voc\u00ea n\u00e3o corre o risco de perder os seus resumos. Um amigo meu perdeu o resumo escrito dele de Direito Tribut\u00e1rio para o cachorro, que aparentemente estava com muita fome (de conhecimento?)! rs<\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 12pt; color: #0000ff;\"><em><span style=\"font-family: georgia, palatino, serif;\">5) F\u00e1cil de ser transportado!<\/span><\/em><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 12pt;\"><span style=\"font-family: georgia, palatino, serif;\">Imagina transportar resumos escritos de 10 disciplinas&#8230; sua mochila teria espa\u00e7o para tudo isso? Um outro amigo meu fazia resumos em fichas (\u00e9 o <a href=\"https:\/\/www.estrategiaconcursos.com.br\/professor\/diego-parreira-3592\/\">Diego Parreira<\/a>, tamb\u00e9m <em>coach<\/em> do Estrat\u00e9gia; conhe\u00e7a a jornada de concurseiro dele clicando <a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/como-fui-aprovado-nas-areas-fiscal-gestao-e-controle\/\">aqui<\/a>) e, quando \u00edamos estudar na biblioteca, l\u00e1 vinha ele com aquelas &#8220;torres&#8221; enormes de fichas.\u00a0 Pela facilidade de armazenamento dos \u00e1udios, voc\u00ea pode contar com eles em qualquer lugar sem adicionar 1 grama de peso \u00e0 sua mochila.<\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 12pt; color: #0000ff;\"><em><span style=\"font-family: georgia, palatino, serif;\">6) F\u00e1cil de ser estudado!<\/span><\/em><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 12pt;\"><span style=\"font-family: georgia, palatino, serif;\">Quando eu estudava para concursos, enfrentava cerca de 3h por dia de tr\u00e2nsito dentro do \u00f4nibus. Dessas 3h, eu tentava aproveitar, pelo menos, 1h30 estudando, a n\u00e3o ser quando eu estava muito cansado, que a\u00ed eu aproveitava para tentar dormir. Mas, mesmo quando eu estava disposto a estudar, ficar lendo alguma coisa no engarrafamento me deixava um pouco enjoado de vez em quando. Ent\u00e3o eu pegava meu celular e ficava ouvindo meus Resumos em \u00c1udio. Se n\u00e3o fosse por isso, eu teria deixado de ganhar umas 4h de estudo de revis\u00e3o por semana. Outras vezes, quando eu almo\u00e7ava sozinho no trabalho, aproveitava tamb\u00e9m para ouvir alguns \u00e1udios sem que ningu\u00e9m percebesse que eu estava estudando.<\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 12pt;\"><span style=\"font-family: georgia, palatino, serif;\">Agora <strong>vamos l\u00e1 ao passo a passo<\/strong> para fazer um bom Resumo em \u00c1udio para a sua mem\u00f3ria&#8230;<\/span><\/span><\/p>\n<p>\u00a0<\/p>\n<div id=\"attachment_48319\" style=\"width: 410px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2016\/09\/05230502\/como-gravar-audio-iphone-1.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-48319\" class=\"wp-image-48319\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2016\/09\/05230502\/como-gravar-audio-iphone-1.jpg\" alt=\"como-gravar-audio-iphone-1\" width=\"400\" height=\"187\" srcset=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2016\/09\/05230502\/como-gravar-audio-iphone-1.jpg 600w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2016\/09\/05230502\/como-gravar-audio-iphone-1.jpg 300w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2016\/09\/05230502\/como-gravar-audio-iphone-1.jpg 500w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><\/a><p id=\"caption-attachment-48319\" class=\"wp-caption-text\"><span style=\"font-size: 12pt;\"><span style=\"font-family: georgia, palatino, serif;\"><em>Apenas com o seu celular, j\u00e1 \u00e9 poss\u00edvel fazer os resumos em \u00e1udio!<\/em><\/span><\/span><\/p><\/div>\n<h2><span style=\"color: #0000ff;\">Equipamentos Necess\u00e1rios<\/span><\/h2>\n<p style=\"text-align: justify;\"><span style=\"font-size: 12pt;\"><span style=\"font-family: georgia, palatino, serif;\">Como eu disse, <strong>voc\u00ea s\u00f3 precisa de um telefone celular com gravador de voz<\/strong>.<\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 12pt;\"><span style=\"font-family: georgia, palatino, serif;\">Mas, caso queira dar uma incrementada no \u00e1udio, fa\u00e7a o seguinte:<\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 12pt;\"><span style=\"font-family: georgia, palatino, serif;\">i) <strong>Use o fone de ouvido para fazer a grava\u00e7\u00e3o<\/strong>. Coloque os fones na orelha e, automaticamente, o microfone do seu fone de ouvido j\u00e1 ficar\u00e1 pr\u00f3ximo da sua boca, em uma boa posi\u00e7\u00e3o para captar sua voz evitando alguns ru\u00eddos do ambiente.<\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 12pt;\"><span style=\"font-family: georgia, palatino, serif;\">ii) Caso o gravador de voz do seu celular n\u00e3o tenha a op\u00e7\u00e3o de <strong>pausar a grava\u00e7\u00e3o<\/strong>, baixe algum aplicativo que a tenha. <span style=\"color: #ff0000;\"><strong>Isso \u00e9 muito importante!<\/strong><\/span> Assim, caso tenha qualquer interrup\u00e7\u00e3o ou d\u00favida enquanto estiver gravando, voc\u00ea pode pausar e resolver o problema. Em seguida, leia o trecho do material que gerou d\u00favidas e volte a gravar dentro do mesmo arquivo.<\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 12pt;\"><span style=\"font-family: georgia, palatino, serif;\">iii) Caso o gravador de voz do seu celular n\u00e3o tenha a op\u00e7\u00e3o de <strong>escolher a qualidade do \u00e1udio<\/strong>, baixe algum aplicativo que a tenha. Pode ser que sua dic\u00e7\u00e3o ou que, at\u00e9 mesmo, o microfone dos seus fones n\u00e3o sejam t\u00e3o bons. Neste caso, alterar a qualidade de grava\u00e7\u00e3o do \u00e1udio pode ajudar.<\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 12pt;\"><span style=\"font-family: georgia, palatino, serif;\">O celular que eu gravava os meus resumos tinha uma qualidade ruim de \u00e1udio e, ainda por cima, n\u00e3o permitia pausar a grava\u00e7\u00e3o. O aplicativo s\u00f3 tinha 2 bot\u00f5es: gravar ou encerrar a grava\u00e7\u00e3o. Se eu apertasse o &#8220;encerrar&#8221;, ele finalizava o arquivo em \u00e1udio. Ent\u00e3o, eu usava o aplicativo &#8220;<span style=\"color: #ff0000;\"><strong>HI-Q MP3 REC (FREE)<\/strong><\/span>&#8221; (tem para Android e iPhone; \u00e9 s\u00f3 pesquisar esse nome na loja de aplicativos do seu celular).<\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 12pt;\"><span style=\"font-family: georgia, palatino, serif;\">Esse aplicativo pausava a grava\u00e7\u00e3o e tamb\u00e9m tinha a op\u00e7\u00e3o de selecionar v\u00e1rios formatos diferentes de qualidade e de formato do \u00e1udio.<\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 12pt;\"><span style=\"font-family: georgia, palatino, serif;\">Ele \u00e9 gratuito mas voc\u00ea s\u00f3 pode gravar \u00e1udios de at\u00e9 10 minutos (acima disso, precisa pagar). Mas isso foi excelente pra mim, pois meu objetivo era nunca ultrapassar 7 minutos de \u00e1udio. Assim a objetividade dos meus \u00e1udios estava assegurada! ;)<\/span><\/span><\/p>\n<p>\u00a0<\/p>\n<div id=\"attachment_48322\" style=\"width: 660px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2016\/09\/05230714\/hi-q.png\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-48322\" class=\"wp-image-48322\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2016\/09\/05230714\/hi-q.png\" alt=\"hi-q\" width=\"650\" height=\"366\" srcset=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2016\/09\/05230714\/hi-q.png 1024w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2016\/09\/05230714\/hi-q.png 300w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2016\/09\/05230714\/hi-q.png 768w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2016\/09\/05230714\/hi-q.png 500w\" sizes=\"auto, (max-width: 650px) 100vw, 650px\" \/><\/a><p id=\"caption-attachment-48322\" class=\"wp-caption-text\"><span style=\"font-size: 12pt;\"><span style=\"font-family: georgia, palatino, serif;\"><em>Hi-Q MP3 REC. Tem para Android e iPhone. Mas h\u00e1 tamb\u00e9m outros gravadores legais gratuitos.<\/em><\/span><\/span><\/p><\/div>\n<p style=\"text-align: justify;\"><span style=\"font-size: 12pt;\"><span style=\"font-family: georgia, palatino, serif;\">\u00a0<\/span><\/span><\/p>\n<h2><span style=\"color: #0000ff;\">Partindo das MP&#8217;s (Marca\u00e7\u00f5es Preliminares)<\/span><\/h2>\n<p style=\"text-align: justify;\"><span style=\"font-size: 12pt;\"><span style=\"font-family: georgia, palatino, serif;\">Resumir em \u00e1udio \u00e9 f\u00e1cil. O dif\u00edcil \u00e9 <strong>fazer isso com objetividade<\/strong>, sem gastar tempo e utilizando as informa\u00e7\u00f5es mais relevantes!<\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 12pt;\"><span style=\"font-family: georgia, palatino, serif;\">Afinal, voc\u00ea quer ser aprovado o quanto antes, correto? E, para isso, temos sempre que <strong>otimizar o nosso tempo<\/strong>. <\/span><\/span><span style=\"font-size: 12pt;\"><span style=\"font-family: georgia, palatino, serif;\">Ent\u00e3o, para conseguir isso, recomendo que voc\u00ea fa\u00e7a as MP&#8217;s antes de come\u00e7ar a grava\u00e7\u00e3o dos seus \u00e1udios.<\/span><\/span><\/p>\n<p style=\"text-align: right;\"><span style=\"font-size: 10pt;\"><em>Otimiza\u00e7\u00e3o do estudo \u00e9 tudo! <\/em><\/span><br \/><span style=\"font-size: 10pt;\"><em>Voc\u00ea pode estudar da maneira mais errada poss\u00edvel, mas ser\u00e1 aprovado se n\u00e3o desistir.<\/em><\/span><br \/><span style=\"font-size: 10pt;\"><em>Utilize os <strong>relat\u00f3rios estat\u00edsticos<\/strong> e <strong>bizus<\/strong> por assunto do Passo Estrat\u00e9gico para otimizar os seus estudos.<\/em><\/span><br \/><span style=\"font-size: 10pt;\"><em>Conhe\u00e7a o <strong>Passo Estrat\u00e9gico<\/strong> clicando <a href=\"http:\/\/bit.ly\/PassoEstrategicoLista\">aqui<\/a>.<\/em><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 12pt;\"><span style=\"font-family: georgia, palatino, serif;\">\u00c9 importante lembrar que, <strong>quanto mais \u00edntimo voc\u00ea estiver do assunto que voc\u00ea quer resumir em \u00e1udio, melhor ficar\u00e1 o seu resumo<\/strong>, mais objetivo, com mais informa\u00e7\u00f5es relevantes e mais personalizado para as suas necessidades.\u00a0Quando digo &#8220;boa intimidade&#8221;, quero dizer: ter estudado toda a teoria daquele assunto, feito os exerc\u00edcios e &#8220;controle de qualidade&#8221; nas marca\u00e7\u00f5es e tamb\u00e9m j\u00e1 ter revisado o assunto, pelo menos, uma vez (que \u00e9 o qu\u00ea voc\u00ea acaba fazendo com as MP&#8217;s).<\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 12pt;\"><span style=\"font-family: georgia, palatino, serif;\">Fazendo isso &#8212; posso dizer isso por experi\u00eancia pr\u00f3pria &#8212; voc\u00ea conseguir\u00e1 resumir uma aula inteira do Estrat\u00e9gia (em v\u00eddeo ou material escrito) em cerca de 4~6 minutos de \u00e1udio.<\/span><\/span><\/p>\n<p>\u00a0<\/p>\n<div id=\"attachment_48323\" style=\"width: 660px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2016\/09\/05231208\/ouvindo-musicas.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-48323\" class=\"wp-image-48323\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2016\/09\/05231208\/ouvindo-musicas.jpg\" alt=\"ouvindo-musicas\" width=\"650\" height=\"458\" srcset=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2016\/09\/05231208\/ouvindo-musicas.jpg 750w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2016\/09\/05231208\/ouvindo-musicas.jpg 300w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2016\/09\/05231208\/ouvindo-musicas.jpg 425w\" sizes=\"auto, (max-width: 650px) 100vw, 650px\" \/><\/a><p id=\"caption-attachment-48323\" class=\"wp-caption-text\"><span style=\"font-size: 12pt;\"><span style=\"font-family: georgia, palatino, serif;\"><em>Eu n\u00e3o ouvia os meus resumos em \u00e1udio com essa felicidade toda! Mas eles certamente me fizeram economizar bastante tempo na minha prepara\u00e7\u00e3o.<\/em><\/span><\/span><\/p><\/div>\n<h2><span style=\"color: #0000ff;\">Gravando&#8230;<\/span><\/h2>\n<p style=\"text-align: justify;\"><span style=\"font-size: 12pt;\"><span style=\"font-family: georgia, palatino, serif;\">#1) V\u00e1 a algum\u00a0lugar silencioso mas que, preferencialmente, n\u00e3o fa\u00e7a eco enquanto voc\u00ea fala.<\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 12pt;\"><span style=\"font-family: georgia, palatino, serif;\">#2) Tenha o\u00a0material que voc\u00ea quer resumir \u00e0 sua frente, j\u00e1 com as MP&#8217;s feitas.<\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 12pt;\"><span style=\"font-family: georgia, palatino, serif;\">#3) Coloque os fones nos ouvidos e certifique-se de que o microfone do fone esteja pr\u00f3xima \u00e0 sua boca.<\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 12pt;\"><span style=\"font-family: georgia, palatino, serif;\">#4) Deixe o celular no modo &#8220;avi\u00e3o&#8221; para n\u00e3o correr o risco de algu\u00e9m te ligar quando voc\u00ea estiver finalizando um \u00e1udio e acabar perdendo tudo que estava gravando. J\u00e1 aconteceu comigo! rs<\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 12pt;\"><span style=\"font-family: georgia, palatino, serif;\">#5) Antes de apertar o bot\u00e3o para gravar, j\u00e1 visualize o assunto que vai gravar. Isso vai deixar o seu \u00e1udio mais objetivo! Por exemplo&#8230; se determinado t\u00f3pico de um assunto de Direito Constitucional foi abordado em 4 p\u00e1ginas do seu livro\/pdf, ent\u00e3o v\u00e1 dar uma olhada nas MPs feitas nessas 4 p\u00e1ginas\u00a0antes de apertar o bot\u00e3o para gravar.<\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 12pt;\"><span style=\"font-family: georgia, palatino, serif;\">#6) Ap\u00f3s gravar um t\u00f3pico de assunto, pause antes de seguir para o assunto seguinte. Mesmo que voc\u00ea se sinta confiante para sair emendando, \u00e9 sempre v\u00e1lido pausar, revisar as p\u00e1ginas do t\u00f3pico seguinte e ent\u00e3o pensar, por alguns segundos, no que pretende falar sobre aquele pr\u00f3ximo assunto.<\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 12pt;\"><span style=\"font-family: georgia, palatino, serif;\">#7) Ap\u00f3s gravar todo o \u00e1udio, encerre a grava\u00e7\u00e3o e nomeie o arquivo de forma que possa identificar o que foi gravado ali. Eu nomeava os arquivos dos meus \u00e1udios de forma bem simples: conforme as aulas dos cursos em <em>pdf<\/em> que eu resumia. Exemplo: &#8220;ECO aula 00&#8221;, &#8220;DCO aula 03&#8221;, &#8220;DCIV aula 01&#8221; etc.<\/span><\/span><\/p>\n<p>\u00a0<\/p>\n<h2><span style=\"color: #0000ff;\">Como utilizar o seu Resumo em \u00c1udio<\/span><\/h2>\n<p style=\"text-align: justify;\"><span style=\"font-size: 12pt;\"><span style=\"font-family: georgia, palatino, serif;\">Como eu disse antes, eu ouvia os meus resumos em momentos em que ficar lendo se mostrava inconveniente: no \u00f4nibus, no engarrafamento, almo\u00e7ando, na fila de espera do banco ou do m\u00e9dico, fazendo atividades repetitivas no trabalho (tirar muitas <em>xerox<\/em>, imprimir algo).<\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 12pt;\"><span style=\"font-family: georgia, palatino, serif;\">Mas cheguei a tentar ouvir os \u00e1udios em outras ocasi\u00f5es e recomendo o seguinte: <strong>n\u00e3o ou\u00e7a os \u00e1udios se estiver fazendo algo que tamb\u00e9m demande sua aten\u00e7\u00e3o<\/strong>, como digitando algo importante no computador, dirigindo em um engarrafamento &#8220;pesado&#8221;, fazendo atividade f\u00edsica etc. Eu, particularmente, percebia que n\u00e3o conseguia reter nada se estivesse dando alguma aten\u00e7\u00e3o a qualquer outra coisa.<\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 12pt;\"><span style=\"font-family: georgia, palatino, serif;\">\u00c0s vezes, at\u00e9 mesmo no engarrafamento, se eu come\u00e7asse a deixar de dar aten\u00e7\u00e3o ao \u00e1udio, quando eu percebia, estava pensando na &#8220;morte da bezerra&#8221;, em alguma piada engra\u00e7ada, lembrando de algum filme ou qualquer outra coisa.<\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 12pt;\"><span style=\"font-family: georgia, palatino, serif;\">Ent\u00e3o \u00e9 necess\u00e1rio ter aten\u00e7\u00e3o ao que voc\u00ea est\u00e1 ouvindo para que os resumos em \u00e1udio sejam eficazes. A ideia \u00e9 que sejam informais como uma conversa. A diferen\u00e7a \u00e9 que a outra pessoa \u00e9 voc\u00ea mesmo, por\u00e9m explicando a mat\u00e9ria&#8230; ou seja, uma conversa muito interessante! rs.<\/span><\/span><\/p>\n<p>\u00a0<\/p>\n<h2><span style=\"color: #0000ff;\">Meu Exemplo<\/span><\/h2>\n<p style=\"text-align: justify;\"><span style=\"font-size: 12pt;\"><span style=\"font-family: georgia, palatino, serif;\">Para exemplificar o que eu estou dizendo, olhe o exemplo abaixo do racioc\u00ednio a ser utilizado em um determinado assunto que \u00e9 estudado em Macroeconomia&#8230; (clique no bot\u00e3o play &#8220;laranja&#8221; no campo superior esquerdo do quadro abaixo)<\/span><\/span><\/p>\n<p><iframe loading=\"lazy\" title=\"Economia - IS LM (Primeira Parte) by Luis Pereira\" width=\"500\" height=\"400\" scrolling=\"no\" frameborder=\"no\" src=\"https:\/\/w.soundcloud.com\/player\/?visual=true&#038;url=https%3A%2F%2Fapi.soundcloud.com%2Ftracks%2F281567735&#038;show_artwork=true&#038;maxheight=750&#038;maxwidth=500\"><\/iframe><\/p>\n<p>\u00a0<\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 12pt;\"><span style=\"font-family: georgia, palatino, serif;\">Esse \u00e1udio de menos de 3 minutos aborda o conhecimento presente em cerca de 50 p\u00e1ginas de uma aula. <\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 12pt;\"><span style=\"font-family: georgia, palatino, serif;\">O \u00e1udio ainda poderia ter ficado mais objetivo pois eu falei t\u00f3picos do assunto &#8220;IS-LM&#8221; que s\u00e3o b\u00e1sicos e que poderiam ter ficado de fora. A ideia, como eu falei, \u00e9 que o \u00e1udio contenha apenas o que \u00e9 necess\u00e1rio para a SUA revis\u00e3o. Cada um tem um ponto fraco no seu conhecimento. E os resumos devem abordar esses pontos. <\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 12pt;\"><span style=\"font-family: georgia, palatino, serif;\">Logo, por exemplo, se voc\u00ea j\u00e1 decorou que uma Emenda Constitucional precisa de aprova\u00e7\u00e3o em cada Casa do Congresso Nacional, em 2 turnos, com m\u00ednimo de 3\/5 dos votos de seus membros, ent\u00e3o isso n\u00e3o precisa constar no seu resumo, correto?<\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 12pt;\"><span style=\"font-family: georgia, palatino, serif;\">Pense dessa forma e os seus resumos ficar\u00e3o s\u00f3 com as informa\u00e7\u00f5es que voc\u00ea realmente precisa para o concurso!<\/span><\/span><\/p>\n<p>\u00a0<\/p>\n<h2><span style=\"color: #0000ff;\">Em qual momento devo fazer esses Resumos em \u00c1udio?<\/span><\/h2>\n<p style=\"text-align: justify;\"><span style=\"font-size: 12pt;\"><span style=\"font-family: georgia, palatino, serif;\">Quanto ao momento de fazer o resumo em \u00e1udio, as \u00fanicas restri\u00e7\u00f5es que eu recomendo s\u00e3o aquelas que eu disse l\u00e1 em cima:<br \/>(1) que voc\u00ea j\u00e1 tenha intimidade com o assunto e (2) que voc\u00ea j\u00e1 tenha feito as MPs no seu material de estudo. <\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 12pt;\"><span style=\"font-family: georgia, palatino, serif;\">Tendo esses 2 requisitos, a\u00ed voc\u00ea pode fazer os resumos em \u00e1udio quando quiser (antes ou depois do edital, perto da prova etc) pois os \u00e1udios n\u00e3o demoram para serem feitos. Ou seja, o ato de &#8220;fazer&#8221; o Resumos em \u00c1udio \u00e9 muito r\u00e1pido! Muito mais do que fazer qualquer resumo escrito, por mais que voc\u00ea seja o Mestre dos Resumos Escritos! rs&#8230; Essa rapidez ocorre apenas se voc\u00ea cumprir os 2 requisitos que eu citei (ter intimidade e ter as MP&#8217;s). <\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 12pt;\"><span style=\"font-family: georgia, palatino, serif;\">Refor\u00e7o: se voc\u00ea for fazer Resumos em \u00c1udio de um assunto que voc\u00ea n\u00e3o tenha intimidade ou as MP&#8217;s para gui\u00e1-lo durante a grava\u00e7\u00e3o do \u00e1udio, ent\u00e3o pode ter certeza de que os seus \u00e1udios ficar\u00e3o GIGANTES!<\/span><\/span><\/p>\n<p>\u00a0<\/p>\n<h2><span style=\"color: #0000ff;\">Repeti\u00e7\u00e3o, repeti\u00e7\u00e3o, repeti\u00e7\u00e3o&#8230;<\/span><\/h2>\n<p style=\"text-align: justify;\"><span style=\"font-size: 12pt;\"><span style=\"font-family: georgia, palatino, serif;\">De posse dos meus \u00e1udios de 4 a 6 minutos por aula, eu adotava a estrat\u00e9gia de tocar cada \u00e1udio 2 ou 3 vezes antes de passar para o \u00e1udio seguinte. Fa\u00e7a isso e, com o tempo, perceber\u00e1 que come\u00e7ar\u00e1 a memorizar at\u00e9 as piores notas de rodap\u00e9 do seu material. E isso tudo em perder tempo sentado fazendo resumos escritos!<\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 12pt;\"><span style=\"font-family: georgia, palatino, serif;\">\u00a0<\/span><\/span><\/p>\n<h2><span style=\"color: #0000ff;\">Conclus\u00e3o<\/span><\/h2>\n<p style=\"text-align: justify;\"><span style=\"font-size: 12pt;\"><span style=\"font-family: georgia, palatino, serif;\">Apesar do artigo ter ficado grande, fazer resumos em \u00e1udio n\u00e3o \u00e9 complicado!<br \/><\/span><\/span><span style=\"font-size: 12pt;\"><span style=\"font-family: georgia, palatino, serif;\">Sabendo fazer as MP&#8217;s, voc\u00ea j\u00e1 ter\u00e1 feito a maior parte. Depois \u00e9 s\u00f3 gravar!<br \/><\/span><\/span><span style=\"font-size: 12pt;\"><span style=\"font-family: georgia, palatino, serif;\">Experimente hoje mesmo esta t\u00e9cnica em alguma aula ou cap\u00edtulo do seu livro e depois conte aqui nos coment\u00e1rios para a gente!<\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 12pt;\"><span style=\"font-family: georgia, palatino, serif;\">Espero ter ajudado!\u00a0Bons estudos e grande abra\u00e7o!<\/span><\/span><\/p>\n<p>\u00a0<\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 12pt;\"><span style=\"font-family: georgia, palatino, serif;\">Para mais dicas sobre prepara\u00e7\u00e3o para concursos e t\u00e9cnicas de estudo, acompanhe atrav\u00e9s do link abaixo:<\/span><\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"font-size: 18pt;\"><a href=\"http:\/\/bit.ly\/TecnicasEstudo\">http:\/\/bit.ly\/TecnicasEstudo<\/a><\/span><\/p>\n<p><span style=\"font-size: 12pt;\"><span style=\"font-family: georgia, palatino, serif;\">E conhe\u00e7a tamb\u00e9m o Estrat\u00e9gia Cast: o aplicativo de aulas em \u00e1udio do Estrat\u00e9gia.<\/span><\/span><\/p>\n<p>\u00a0<\/p>\n<h2><span style=\"color: #0000ff;\">Estrat\u00e9gia Cast<\/span><\/h2>\n<p>Conhe\u00e7a o Estrat\u00e9gia Cast: <a href=\"https:\/\/www.estrategiacast.com.br\/\">https:\/\/www.estrategiacast.com.br\/<\/a><\/p>\n<p>Bons estudos!<\/p>\n<div><em>\u00a0<\/em><\/div>\n<div class=\"gmail_default\"><em><strong>\u200bLuis Eduardo<\/strong><\/em><\/div>\n<div><em>Coach e Analista do Passo Estrat\u00e9gico<\/em><\/div>\n<div><em>Auditor Fiscal do Estado de S\u00e3o Paulo<\/em><\/div>\n<div><em>Conhe\u00e7a o <a href=\"https:\/\/www.estrategiaconcursos.com.br\/cursosPorConcurso\/coaching-382\/\">Programa de Coaching do Estrat\u00e9gia Concursos<\/a>\u00a0<\/em><\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Resumos em \u00c1udio Eles economizam tempo, s\u00e3o f\u00e1ceis de serem constru\u00eddos e permitem o estudo em qualquer lugar, a qualquer momento!Esses s\u00e3o os Resumos em \u00c1udio! Vamos falar um pouco sobre isso?! Eu gostaria de contar para voc\u00ea como essa T\u00e9cnica de Estudo me ajudou a ganhar confian\u00e7a e ficar bom em disciplinas que eu [&hellip;]<\/p>\n","protected":false},"author":344,"featured_media":48313,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"post_tipo":"article","footnotes":""},"categories":[1],"tags":[594,861,943,723,3022,1195],"tax_estado":[],"class_list":["post-48299","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cursos-e-concursos","tag-como-estudar-para-concursos","tag-dicas-de-estudo","tag-dicas-de-estudos","tag-estrategia-concursos","tag-resumos-em-audio","tag-tecnicas-de-estudo"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.2 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Resumos em \u00c1udio para Concursos P\u00fablicos: passo a passo!<\/title>\n<meta name=\"description\" content=\"R\u00e1pido e f\u00e1cil de ser feito! Al\u00e9m de ser uma das melhores T\u00e9cnicas de Estudo para memoriza\u00e7\u00e3o! Veja o passo a passo para montar os seus Resumos em \u00c1udio!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumos-em-audio\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Resumos em \u00c1udio: passo a passo!\" \/>\n<meta property=\"og:description\" content=\"R\u00e1pido e f\u00e1cil de ser feito! Al\u00e9m de ser uma das melhores T\u00e9cnicas de Estudo para memoriza\u00e7\u00e3o! Veja o passo a passo para montar os seus Resumos em \u00c1udio!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumos-em-audio\/\" \/>\n<meta property=\"og:site_name\" content=\"Estrat\u00e9gia Concursos\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/coachluiseduardo\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-01-04T14:30:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-04-14T14:12:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2016\/09\/05225852\/ursinho-ouvindo-musica-3321.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Luis Eduardo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:site\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Luis Eduardo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"12 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumos-em-audio\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumos-em-audio\/\"},\"author\":{\"name\":\"Luis Eduardo\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/0906ff564105056f3b05978d503ee214\"},\"headline\":\"Resumos em \u00c1udio: passo a passo!\",\"datePublished\":\"2020-01-04T14:30:00+00:00\",\"dateModified\":\"2023-04-14T14:12:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumos-em-audio\/\"},\"wordCount\":2470,\"commentCount\":31,\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumos-em-audio\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2016\/09\/05225852\/ursinho-ouvindo-musica-3321.jpg\",\"keywords\":[\"Como estudar para concursos\",\"dicas de estudo\",\"dicas de estudos\",\"Estrat\u00e9gia Concursos\",\"Resumos em \u00c1udio\",\"t\u00e9cnicas de estudo\"],\"articleSection\":[\"Concursos P\u00fablicos\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumos-em-audio\/#respond\"]}],\"copyrightYear\":\"2020\",\"copyrightHolder\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumos-em-audio\/\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumos-em-audio\/\",\"name\":\"Resumos em \u00c1udio para Concursos P\u00fablicos: passo a passo!\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumos-em-audio\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumos-em-audio\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2016\/09\/05225852\/ursinho-ouvindo-musica-3321.jpg\",\"datePublished\":\"2020-01-04T14:30:00+00:00\",\"dateModified\":\"2023-04-14T14:12:38+00:00\",\"description\":\"R\u00e1pido e f\u00e1cil de ser feito! Al\u00e9m de ser uma das melhores T\u00e9cnicas de Estudo para memoriza\u00e7\u00e3o! Veja o passo a passo para montar os seus Resumos em \u00c1udio!\",\"breadcrumb\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumos-em-audio\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumos-em-audio\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumos-em-audio\/#primaryimage\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2016\/09\/05225852\/ursinho-ouvindo-musica-3321.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2016\/09\/05225852\/ursinho-ouvindo-musica-3321.jpg\",\"width\":1600,\"height\":1200},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumos-em-audio\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Resumos em \u00c1udio: passo a passo!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"name\":\"Estrat\u00e9gia Concursos\",\"description\":\"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.\",\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\",\"name\":\"Estrat\u00e9gia Concursos\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"width\":230,\"height\":60,\"caption\":\"Estrat\u00e9gia Concursos\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/EstratConcursos\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/0906ff564105056f3b05978d503ee214\",\"name\":\"Luis Eduardo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/3ce09d3c01f86018c4f3b15b9e6389f2ac325bc19863fdb79cd37fefb38517d1?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/3ce09d3c01f86018c4f3b15b9e6389f2ac325bc19863fdb79cd37fefb38517d1?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/3ce09d3c01f86018c4f3b15b9e6389f2ac325bc19863fdb79cd37fefb38517d1?s=96&d=mm&r=g\",\"caption\":\"Luis Eduardo\"},\"sameAs\":[\"https:\/\/www.facebook.com\/coachluiseduardo\/\"],\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/luiseduardoestrategiaconcursos-com-br\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Resumos em \u00c1udio para Concursos P\u00fablicos: passo a passo!","description":"R\u00e1pido e f\u00e1cil de ser feito! Al\u00e9m de ser uma das melhores T\u00e9cnicas de Estudo para memoriza\u00e7\u00e3o! Veja o passo a passo para montar os seus Resumos em \u00c1udio!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumos-em-audio\/","og_locale":"pt_BR","og_type":"article","og_title":"Resumos em \u00c1udio: passo a passo!","og_description":"R\u00e1pido e f\u00e1cil de ser feito! Al\u00e9m de ser uma das melhores T\u00e9cnicas de Estudo para memoriza\u00e7\u00e3o! Veja o passo a passo para montar os seus Resumos em \u00c1udio!","og_url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumos-em-audio\/","og_site_name":"Estrat\u00e9gia Concursos","article_author":"https:\/\/www.facebook.com\/coachluiseduardo\/","article_published_time":"2020-01-04T14:30:00+00:00","article_modified_time":"2023-04-14T14:12:38+00:00","og_image":[{"width":1600,"height":1200,"url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2016\/09\/05225852\/ursinho-ouvindo-musica-3321.jpg","type":"image\/jpeg"}],"author":"Luis Eduardo","twitter_card":"summary_large_image","twitter_creator":"@EstratConcursos","twitter_site":"@EstratConcursos","twitter_misc":{"Escrito por":"Luis Eduardo","Est. tempo de leitura":"12 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumos-em-audio\/#article","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumos-em-audio\/"},"author":{"name":"Luis Eduardo","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/0906ff564105056f3b05978d503ee214"},"headline":"Resumos em \u00c1udio: passo a passo!","datePublished":"2020-01-04T14:30:00+00:00","dateModified":"2023-04-14T14:12:38+00:00","mainEntityOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumos-em-audio\/"},"wordCount":2470,"commentCount":31,"publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumos-em-audio\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2016\/09\/05225852\/ursinho-ouvindo-musica-3321.jpg","keywords":["Como estudar para concursos","dicas de estudo","dicas de estudos","Estrat\u00e9gia Concursos","Resumos em \u00c1udio","t\u00e9cnicas de estudo"],"articleSection":["Concursos P\u00fablicos"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/resumos-em-audio\/#respond"]}],"copyrightYear":"2020","copyrightHolder":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumos-em-audio\/","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumos-em-audio\/","name":"Resumos em \u00c1udio para Concursos P\u00fablicos: passo a passo!","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumos-em-audio\/#primaryimage"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumos-em-audio\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2016\/09\/05225852\/ursinho-ouvindo-musica-3321.jpg","datePublished":"2020-01-04T14:30:00+00:00","dateModified":"2023-04-14T14:12:38+00:00","description":"R\u00e1pido e f\u00e1cil de ser feito! Al\u00e9m de ser uma das melhores T\u00e9cnicas de Estudo para memoriza\u00e7\u00e3o! Veja o passo a passo para montar os seus Resumos em \u00c1udio!","breadcrumb":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumos-em-audio\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/resumos-em-audio\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumos-em-audio\/#primaryimage","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2016\/09\/05225852\/ursinho-ouvindo-musica-3321.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2016\/09\/05225852\/ursinho-ouvindo-musica-3321.jpg","width":1600,"height":1200},{"@type":"BreadcrumbList","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumos-em-audio\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.estrategiaconcursos.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Resumos em \u00c1udio: passo a passo!"}]},{"@type":"WebSite","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","name":"Estrat\u00e9gia Concursos","description":"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.","publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization","name":"Estrat\u00e9gia Concursos","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","width":230,"height":60,"caption":"Estrat\u00e9gia Concursos"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/EstratConcursos"]},{"@type":"Person","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/0906ff564105056f3b05978d503ee214","name":"Luis Eduardo","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/3ce09d3c01f86018c4f3b15b9e6389f2ac325bc19863fdb79cd37fefb38517d1?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/3ce09d3c01f86018c4f3b15b9e6389f2ac325bc19863fdb79cd37fefb38517d1?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3ce09d3c01f86018c4f3b15b9e6389f2ac325bc19863fdb79cd37fefb38517d1?s=96&d=mm&r=g","caption":"Luis Eduardo"},"sameAs":["https:\/\/www.facebook.com\/coachluiseduardo\/"],"url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/luiseduardoestrategiaconcursos-com-br\/"}]}},"_links":{"self":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/48299","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/users\/344"}],"replies":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/comments?post=48299"}],"version-history":[{"count":40,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/48299\/revisions"}],"predecessor-version":[{"id":1201709,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/48299\/revisions\/1201709"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media\/48313"}],"wp:attachment":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media?parent=48299"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/categories?post=48299"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tags?post=48299"},{"taxonomy":"tax_estado","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tax_estado?post=48299"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}