{"id":469635,"date":"2020-01-15T11:12:30","date_gmt":"2020-01-15T14:12:30","guid":{"rendered":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?p=469635"},"modified":"2023-04-11T11:44:50","modified_gmt":"2023-04-11T14:44:50","slug":"aprenda-utilizar-salas-vip","status":"publish","type":"post","link":"https:\/\/www.estrategiaconcursos.com.br\/blog\/aprenda-utilizar-salas-vip\/","title":{"rendered":"Aprenda a utilizar as Salas VIP"},"content":{"rendered":"\n<p>Saiba tudo\nsobre a novidade que aproximou ainda mais os nossos alunos dos coaches,\naprovados e professores: as Salas VIP!<\/p>\n\n\n\n<p>Ol\u00e1, pessoal! Tudo bem?<\/p>\n\n\n\n<p>Neste in\u00edcio de ano, assim como j\u00e1 havia ocorrido em 2019, fizemos um super  lan\u00e7amento que revolucionou o mercado de concursos p\u00fablicos. Foram 4 novidades: 1) Olimp\u00edada de Simulados; 2) Salas VIP; 3) Fundador de Sistema de Quest\u00f5es; e 4) Marca\u00e7\u00e3o dos Aprovados.<\/p>\n\n\n\n<p>J\u00e1 fiz um artigo explicando sobre a <a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/como-se-inscrever-na-olimpiada-de-simulados\/\">Olimp\u00edada de Simulados<\/a>. <\/p>\n\n\n\n<p>Hoje falarei sobre a <strong>segunda novidade<\/strong> e explicarei os principais pontos que voc\u00ea precisa conhecer para participar das Salas VIP.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-o-que-sao-as-salas-vip\">O que s\u00e3o as Salas VIP?<\/h2>\n\n\n\n<p>Antes de come\u00e7ar, \u00e9 importante\ndestacar que as Salas VIP s\u00e3o&nbsp;<strong>gratuitas para os assinantes<\/strong>, pois o\nnosso objetivo \u00e9 sempre fornecer o melhor conte\u00fado para aqueles que confiam em\nnosso trabalho.<\/p>\n\n\n\n<p>As Salas VIP s\u00e3o salas virtuais interativas, que contam com 4 ou 12 participantes, a depender do assunto abordado, e t\u00eam dura\u00e7\u00e3o m\u00e1xima de 1 hora. <\/p>\n\n\n\n<p>Funcionam igual a uma videoconfer\u00eancia, contando com recursos de \u00e1udio, v\u00eddeo e chat. <\/p>\n\n\n\n<p>\u00c9 um verdadeiro bate-papo, que possibilita a aproxima\u00e7\u00e3o dos coaches, aprovados e professores com os nossos alunos.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-quem-podera-usar-as-salas-vip\">Quem poder\u00e1 usar as Salas VIP?<\/h2>\n\n\n\n<p>Como dito, as salas virtuais\ninterativas destinam-se a todos os alunos assinantes que queiram ter um <strong>atendimento\nindividualizado<\/strong> para dirimir alguma d\u00favida espec\u00edfica ou at\u00e9 mesmo para dar\numa dire\u00e7\u00e3o aos seus estudos.<\/p>\n\n\n\n<p>Inicialmente, h\u00e1 salas sobre <strong>10 diferentes temas<\/strong>, os quais ser\u00e3o explicados detalhadamente nos pr\u00f3ximos t\u00f3picos. As salas s\u00e3o divididas em hor\u00e1rios e dias diversos, de modo que o aluno consiga encontrar um hor\u00e1rio que se encaixe na sua rotina.<\/p>\n\n\n\n<p>Ou seja, o aluno escolhe qual o tema\ndeseja trabalhar e, a partir da\u00ed, opta entre os in\u00fameros hor\u00e1rios que est\u00e3o a\nsua disposi\u00e7\u00e3o.<\/p>\n\n\n\n<p>Para se ter uma ideia, s\u00e3o cerca de <strong>15 salas em um \u00fanico dia, das 5 \u00e0s 23 horas<\/strong>. N\u00e3o tem desculpa para n\u00e3o acessar!<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-como-acessar-as-salas-vip\">Como acessar as Salas VIP?<\/h2>\n\n\n\n<p>Para acessar a uma Sala VIP, o aluno deve ingressar em sua \u00e1rea do aluno assinante e, na aba lateral esquerda, clicar em \u201cSala Vip\u201d. <\/p>\n\n\n\n<p>Ao lado direito, aparecer\u00e1 um calend\u00e1rio com os dias e hor\u00e1rios das salas, separadas por assunto. Basta clicar no link azul, na caixa cinza, ao lado do calend\u00e1rio.<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"654\" height=\"342\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/01\/13221227\/Como-utilizar-as-Salas-VIP-acesso-1.jpg\" alt=\"Como utilizar as Salas VIP\" class=\"wp-image-469636\" srcset=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/01\/13221227\/Como-utilizar-as-Salas-VIP-acesso-1.jpg 654w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/01\/13221227\/Como-utilizar-as-Salas-VIP-acesso-1-300x157.jpg 300w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/01\/13221227\/Como-utilizar-as-Salas-VIP-acesso-1-610x319.jpg 610w\" sizes=\"auto, (max-width: 654px) 100vw, 654px\" \/><figcaption class=\"wp-element-caption\">Calend\u00e1rio das Salas VIP<\/figcaption><\/figure>\n\n\n\n<p>Outra forma de acesso \u00e9 selecionar o assunto desejado, abaixo do calend\u00e1rio, e clicar sobre o dia e hor\u00e1rio de interesse.<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"423\" height=\"223\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/01\/13221417\/Como-utilizar-as-Salas-VIP-acesso-2.jpg\" alt=\"Como utilizar as Salas VIP\" class=\"wp-image-469637\" srcset=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/01\/13221417\/Como-utilizar-as-Salas-VIP-acesso-2.jpg 423w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/01\/13221417\/Como-utilizar-as-Salas-VIP-acesso-2-300x158.jpg 300w\" sizes=\"auto, (max-width: 423px) 100vw, 423px\" \/><figcaption class=\"wp-element-caption\">Dias e hor\u00e1rios das Salas VIP<\/figcaption><\/figure>\n\n\n\n<p>Ap\u00f3s isso, aparecer\u00e3o dois bot\u00f5es: a) Baixar livro eletr\u00f4nico, o qual cont\u00e9m as orienta\u00e7\u00f5es de uso da sala; e b) Estude em grupo, o qual direcionar\u00e1 o aluno para a sala virtual interativa.<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"611\" height=\"292\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/01\/13221525\/Como-utilizar-as-Salas-VIP-acesso-3.jpg\" alt=\"Como utilizar as Salas VIP\" class=\"wp-image-469638\" srcset=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/01\/13221525\/Como-utilizar-as-Salas-VIP-acesso-3.jpg 611w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/01\/13221525\/Como-utilizar-as-Salas-VIP-acesso-3-300x143.jpg 300w\" sizes=\"auto, (max-width: 611px) 100vw, 611px\" \/><\/figure>\n\n\n\n<p>Tudo muito <strong>simples e pr\u00e1tico<\/strong> para que voc\u00ea n\u00e3o perca tempo!<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-temas-das-salas-vip\">Temas das Salas VIP<\/h2>\n\n\n\n<p>Como as salas virtuais foram criadas com\no intuito de aproximar o aluno da nossa equipe de profissionais, pensamos em\ndividi-las em temas para <strong>facilitar a intera\u00e7\u00e3o dos membros<\/strong>.<\/p>\n\n\n\n<p>Assim, foram separados os t\u00f3picos que\ngeram maior quantidade de d\u00favidas e que merecem uma <strong>aten\u00e7\u00e3o mais personalizada<\/strong>,\npois s\u00e3o quest\u00f5es que, geralmente, n\u00e3o possuem um padr\u00e3o de resposta.<\/p>\n\n\n\n<p>Portanto, estes s\u00e3o os temas abordados\nnas salas:<\/p>\n\n\n\n<p>1) <strong>&nbsp;Monte o seu Ciclo:<\/strong> aprenda a planejar,\ncontrolar e distribuir a carga hor\u00e1ria entre as disciplinas a serem estudadas,\ntudo isso de acordo com a sua rotina;<\/p>\n\n\n\n<p>2)&nbsp;\n<strong>Fa\u00e7a o seu Planejamento de Estudos:<\/strong> objetiva auxiliar o aluno na\ntomada de decis\u00f5es acerca do seu plano de estudos;<\/p>\n\n\n\n<p>3)&nbsp;\n<strong>An\u00e1lise de Marca\u00e7\u00f5es:<\/strong> o aluno apresenta o material utilizado no\nseu estudo e o coach faz a an\u00e1lise dos grifos, de modo a identificar poss\u00edveis\npontos de melhoria;<\/p>\n\n\n\n<p>4)&nbsp;\n<strong>An\u00e1lise de Resumos:<\/strong> a sistem\u00e1tica \u00e9 semelhante \u00e0 an\u00e1lise das\nmarca\u00e7\u00f5es, mas, aqui, o coach verifica os resumos e mapas mentais feitos pelo\naluno;<\/p>\n\n\n\n<p>5)&nbsp;\n<strong>An\u00e1lise de Plano de Estudos:<\/strong> tamb\u00e9m \u00e9 semelhante \u00e0s salas\nanteriores, mas, agora, a an\u00e1lise \u00e9 do plano de estudos;<\/p>\n\n\n\n<p>6)&nbsp;\n<strong>Oficina de Reda\u00e7\u00e3o:<\/strong> o professor orienta os alunos sobre t\u00e9cnicas\nde elabora\u00e7\u00e3o de reda\u00e7\u00f5es, assim como poss\u00edveis temas a serem abordados;<\/p>\n\n\n\n<p>7)&nbsp;\n<strong>Oficina de Discursivas:<\/strong> a sistem\u00e1tica \u00e9 semelhante \u00e0 anterior,\nmas com foco nas quest\u00f5es discursivas, relat\u00f3rios, pe\u00e7as e outras formas de\ndiscursivas; <\/p>\n\n\n\n<p>8)&nbsp; <strong>Fale com um Aprovado:<\/strong> uma oportunidade de o aluno conversar diretamente com um aprovado, podendo perguntar sobre qualquer assunto;<\/p>\n\n\n\n<p>9)&nbsp;\n<strong>Fale com um Coach:<\/strong> \u00e9 uma sala que tamb\u00e9m n\u00e3o possui tema definido,\nmas que ser\u00e1 conduzida por um coach. Assim, como a anterior, possibilita o\nesclarecimento das mais diversas d\u00favidas;<\/p>\n\n\n\n<p>10)&nbsp;\n<strong>Conhe\u00e7a a minha carreira:<\/strong> esta sala contar\u00e1 com um profissional\ndo setor p\u00fablico, o qual apresentar\u00e1 a sua carreira aos alunos, sob um ponto de\nvista mais \u00edntimo.<\/p>\n\n\n\n<p>Voc\u00eas podem perceber que as salas VIP, embora possam conter at\u00e9 12 pessoas, possibilitam um atendimento particularizado, pois a demanda de cada aluno ser\u00e1 respondida por quem est\u00e1 conduzindo a sala.<\/p>\n\n\n\n<p>\u00c9 uma excelente oportunidade de ter a sua d\u00favida sanada ou de receber uma orienta\u00e7\u00e3o espec\u00edfica que dar\u00e1 um rumo aos seus estudos. <\/p>\n\n\n\n<p>Claro que, como todo lan\u00e7amento, existe\numa grande quantidade de alunos interessados em participar das Salas VIP. Por\neste motivo, h\u00e1 salas durante 15 horas do dia, com o objetivo de suprir,\ngradativamente, a demanda de interessados.<\/p>\n\n\n\n<p>E voc\u00ea, que j\u00e1 conhece a Coruja, sabe\nque muitas melhorias ainda est\u00e3o por vir, tais como <strong>fila de espera,\nagendamento e at\u00e9 mesmo a possibilidade de ser espectador<\/strong>.<\/p>\n\n\n\n<p>Por isso, n\u00e3o perca tempo e v\u00e1 logo\nexperimentar mais essa novidade que o Estrat\u00e9gia trouxe para voc\u00ea, assinante!<\/p>\n\n\n\n<p><strong>Abra\u00e7os,<\/strong><\/p>\n\n\n\n<p>Ricardo\nVale<\/p>\n\n\n\n<p><strong>Instagram:<\/strong>&nbsp;<a href=\"https:\/\/www.instagram.com\/profricardovale\/\">@profricardovale<\/a><\/p>\n\n\n\n<p><em>Prepare-se com o melhor material e com quem mais aprova em Concursos P\u00fablicos em todo o pa\u00eds. <\/em><\/p>\n\n\n\n<p class=\"has-text-align-center has-luminous-vivid-amber-background-color has-background\" style=\"font-size:clamp(16.834px, 1.052rem + ((1vw - 3.2px) * 0.899), 26px);px\"><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-abertos\/\"><strong>CONCURSOS ABERTOS<\/strong><\/a><\/p>\n\n\n\n<p class=\"has-text-align-center has-luminous-vivid-amber-background-color has-background\" style=\"font-size:clamp(16.834px, 1.052rem + ((1vw - 3.2px) * 0.899), 26px);px\"><a href=\"https:\/\/www.estrategiaconcursos.com.br\/cursos\/concurso\/\"><strong>CURSOS PARA CONCURSOS<\/strong><\/a> <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Saiba tudo sobre a novidade que aproximou ainda mais os nossos alunos dos coaches, aprovados e professores: as Salas VIP! Ol\u00e1, pessoal! Tudo bem? Neste in\u00edcio de ano, assim como j\u00e1 havia ocorrido em 2019, fizemos um super lan\u00e7amento que revolucionou o mercado de concursos p\u00fablicos. Foram 4 novidades: 1) Olimp\u00edada de Simulados; 2) Salas [&hellip;]<\/p>\n","protected":false},"author":26,"featured_media":469640,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"post_tipo":"article","footnotes":""},"categories":[1],"tags":[],"tax_estado":[],"class_list":["post-469635","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cursos-e-concursos"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.2 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Aprenda a utilizar as Salas VIP<\/title>\n<meta name=\"description\" content=\"Saiba tudo sobre a novidade que aproximou ainda mais os nossos alunos dos coaches, aprovados e professores: as Salas VIP!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/aprenda-utilizar-salas-vip\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Aprenda a utilizar as Salas VIP\" \/>\n<meta property=\"og:description\" content=\"Saiba tudo sobre a novidade que aproximou ainda mais os nossos alunos dos coaches, aprovados e professores: as Salas VIP!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/aprenda-utilizar-salas-vip\/\" \/>\n<meta property=\"og:site_name\" content=\"Estrat\u00e9gia Concursos\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/rvale01\" \/>\n<meta property=\"article:published_time\" content=\"2020-01-15T14:12:30+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-04-11T14:44:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/01\/13222615\/Estrat%C3%A9gia-logo.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"400\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Ricardo Vale\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/EstratConcursos\" \/>\n<meta name=\"twitter:site\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ricardo Vale\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/aprenda-utilizar-salas-vip\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/aprenda-utilizar-salas-vip\/\"},\"author\":{\"name\":\"Ricardo Vale\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/c32e47dba2159cafe7796a9569a6ff7e\"},\"headline\":\"Aprenda a utilizar as Salas VIP\",\"datePublished\":\"2020-01-15T14:12:30+00:00\",\"dateModified\":\"2023-04-11T14:44:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/aprenda-utilizar-salas-vip\/\"},\"wordCount\":1015,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/aprenda-utilizar-salas-vip\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/01\/13222615\/Estrat%C3%A9gia-logo.jpeg\",\"articleSection\":[\"Concursos P\u00fablicos\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/aprenda-utilizar-salas-vip\/#respond\"]}],\"copyrightYear\":\"2020\",\"copyrightHolder\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/aprenda-utilizar-salas-vip\/\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/aprenda-utilizar-salas-vip\/\",\"name\":\"Aprenda a utilizar as Salas VIP\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/aprenda-utilizar-salas-vip\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/aprenda-utilizar-salas-vip\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/01\/13222615\/Estrat%C3%A9gia-logo.jpeg\",\"datePublished\":\"2020-01-15T14:12:30+00:00\",\"dateModified\":\"2023-04-11T14:44:50+00:00\",\"description\":\"Saiba tudo sobre a novidade que aproximou ainda mais os nossos alunos dos coaches, aprovados e professores: as Salas VIP!\",\"breadcrumb\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/aprenda-utilizar-salas-vip\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/aprenda-utilizar-salas-vip\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/aprenda-utilizar-salas-vip\/#primaryimage\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/01\/13222615\/Estrat%C3%A9gia-logo.jpeg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/01\/13222615\/Estrat%C3%A9gia-logo.jpeg\",\"width\":400,\"height\":400},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/aprenda-utilizar-salas-vip\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Aprenda a utilizar as Salas VIP\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"name\":\"Estrat\u00e9gia Concursos\",\"description\":\"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.\",\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\",\"name\":\"Estrat\u00e9gia Concursos\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"width\":230,\"height\":60,\"caption\":\"Estrat\u00e9gia Concursos\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/EstratConcursos\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/c32e47dba2159cafe7796a9569a6ff7e\",\"name\":\"Ricardo Vale\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/e5a5658c798bb49dd53314263f59f38c192d73370fb65839a372c2ae9027be74?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/e5a5658c798bb49dd53314263f59f38c192d73370fb65839a372c2ae9027be74?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/e5a5658c798bb49dd53314263f59f38c192d73370fb65839a372c2ae9027be74?s=96&d=mm&r=g\",\"caption\":\"Ricardo Vale\"},\"sameAs\":[\"https:\/\/www.facebook.com\/rvale01\",\"https:\/\/x.com\/https:\/\/twitter.com\/EstratConcursos\"],\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/ricardovaleestrategiaconcursos-com-br\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Aprenda a utilizar as Salas VIP","description":"Saiba tudo sobre a novidade que aproximou ainda mais os nossos alunos dos coaches, aprovados e professores: as Salas VIP!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.estrategiaconcursos.com.br\/blog\/aprenda-utilizar-salas-vip\/","og_locale":"pt_BR","og_type":"article","og_title":"Aprenda a utilizar as Salas VIP","og_description":"Saiba tudo sobre a novidade que aproximou ainda mais os nossos alunos dos coaches, aprovados e professores: as Salas VIP!","og_url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/aprenda-utilizar-salas-vip\/","og_site_name":"Estrat\u00e9gia Concursos","article_author":"https:\/\/www.facebook.com\/rvale01","article_published_time":"2020-01-15T14:12:30+00:00","article_modified_time":"2023-04-11T14:44:50+00:00","og_image":[{"width":400,"height":400,"url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/01\/13222615\/Estrat%C3%A9gia-logo.jpeg","type":"image\/jpeg"}],"author":"Ricardo Vale","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/EstratConcursos","twitter_site":"@EstratConcursos","twitter_misc":{"Escrito por":"Ricardo Vale","Est. tempo de leitura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/aprenda-utilizar-salas-vip\/#article","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/aprenda-utilizar-salas-vip\/"},"author":{"name":"Ricardo Vale","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/c32e47dba2159cafe7796a9569a6ff7e"},"headline":"Aprenda a utilizar as Salas VIP","datePublished":"2020-01-15T14:12:30+00:00","dateModified":"2023-04-11T14:44:50+00:00","mainEntityOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/aprenda-utilizar-salas-vip\/"},"wordCount":1015,"commentCount":0,"publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/aprenda-utilizar-salas-vip\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/01\/13222615\/Estrat%C3%A9gia-logo.jpeg","articleSection":["Concursos P\u00fablicos"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/aprenda-utilizar-salas-vip\/#respond"]}],"copyrightYear":"2020","copyrightHolder":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/aprenda-utilizar-salas-vip\/","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/aprenda-utilizar-salas-vip\/","name":"Aprenda a utilizar as Salas VIP","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/aprenda-utilizar-salas-vip\/#primaryimage"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/aprenda-utilizar-salas-vip\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/01\/13222615\/Estrat%C3%A9gia-logo.jpeg","datePublished":"2020-01-15T14:12:30+00:00","dateModified":"2023-04-11T14:44:50+00:00","description":"Saiba tudo sobre a novidade que aproximou ainda mais os nossos alunos dos coaches, aprovados e professores: as Salas VIP!","breadcrumb":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/aprenda-utilizar-salas-vip\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/aprenda-utilizar-salas-vip\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/aprenda-utilizar-salas-vip\/#primaryimage","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/01\/13222615\/Estrat%C3%A9gia-logo.jpeg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/01\/13222615\/Estrat%C3%A9gia-logo.jpeg","width":400,"height":400},{"@type":"BreadcrumbList","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/aprenda-utilizar-salas-vip\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.estrategiaconcursos.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Aprenda a utilizar as Salas VIP"}]},{"@type":"WebSite","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","name":"Estrat\u00e9gia Concursos","description":"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.","publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization","name":"Estrat\u00e9gia Concursos","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","width":230,"height":60,"caption":"Estrat\u00e9gia Concursos"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/EstratConcursos"]},{"@type":"Person","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/c32e47dba2159cafe7796a9569a6ff7e","name":"Ricardo Vale","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/e5a5658c798bb49dd53314263f59f38c192d73370fb65839a372c2ae9027be74?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e5a5658c798bb49dd53314263f59f38c192d73370fb65839a372c2ae9027be74?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e5a5658c798bb49dd53314263f59f38c192d73370fb65839a372c2ae9027be74?s=96&d=mm&r=g","caption":"Ricardo Vale"},"sameAs":["https:\/\/www.facebook.com\/rvale01","https:\/\/x.com\/https:\/\/twitter.com\/EstratConcursos"],"url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/ricardovaleestrategiaconcursos-com-br\/"}]}},"_links":{"self":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/469635","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/comments?post=469635"}],"version-history":[{"count":8,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/469635\/revisions"}],"predecessor-version":[{"id":1199938,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/469635\/revisions\/1199938"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media\/469640"}],"wp:attachment":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media?parent=469635"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/categories?post=469635"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tags?post=469635"},{"taxonomy":"tax_estado","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tax_estado?post=469635"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}