{"id":461293,"date":"2022-03-09T00:00:00","date_gmt":"2022-03-09T03:00:00","guid":{"rendered":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?p=461293"},"modified":"2022-03-09T07:56:52","modified_gmt":"2022-03-09T10:56:52","slug":"concurso-coren-se","status":"publish","type":"post","link":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-coren-se\/","title":{"rendered":"Concurso COREN SE: homologado resultado final"},"content":{"rendered":"\n<p>Foi publicado no Di\u00e1rio Oficial da Uni\u00e3o desta quarta-feira (09\/03), a homologa\u00e7\u00e3o do <strong>resultado final <\/strong>do <strong>concurso COREN SE <\/strong>(<a href=\"https:\/\/www.estrategiaconcursos.com.br\/cursos\/concurso\/\" target=\"_blank\" rel=\"noreferrer noopener\">Conselho Regional de Enfermagem de Sergipe<\/a>). <\/p>\n\n\n\n<p><a href=\"https:\/\/www.in.gov.br\/en\/web\/dou\/-\/edital-n-11-coren-se-de-8-de-marco-de-2022-384641591\" target=\"_blank\" rel=\"noreferrer noopener\">Confira aqui <\/a>se seu nome consta na lista de aprovados do concurso p\u00fablico do COREN SE. <\/p>\n\n\n\n<ul id=\"block-ee678516-e9d1-48bd-b327-7b9acd55f0fd\" class=\"has-very-light-gray-to-cyan-bluish-gray-gradient-background has-background wp-block-list\"><li><strong>Concurso COREN SE<\/strong><\/li><li><strong>Status:<\/strong>\u00a0resultado final homologado<\/li><li><strong>Vagas:\u00a0<\/strong>5<\/li><li><strong>Sal\u00e1rio inicial:<\/strong>\u00a0R$ 1.307,42 \/ R$ 4.750,00<\/li><li><strong>Edital:\u00a0<\/strong><a href=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/02\/25091446\/coren-se-edital-1.pdf\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">Edital COREN SE<\/a><\/li><\/ul>\n\n\n\n<div class=\"col-sm\">\n      <div class=\"banner-estrategia\" id=\"box-assinatura\">\n        <h3 class=\"titulo-assinatura\">Cursos para COREN SE<\/h3>\n        <p class=\"subtitulo-assinatura\">Conhe\u00e7a os cursos<\/p>\n        <div class=\"box-botao\">\n          <a class=\"btn-assinatura\" target=\"_blank\" href=\"https:\/\/www.estrategiaconcursos.com.br\/cursosPorConcurso\/conselho-regional-de-enfermagem-de-sergipe-coren-se\/\" role=\"button\" rel=\"noopener noreferrer\">Conhe\u00e7a mais<\/a>\n        <\/div>\n      <\/div>\n      <p class=\"texto-auxiliar\">Prepare-se com o melhor material e com quem mais aprova em Concursos P\u00fablicos em todo o pa\u00eds.<\/p>\n    <\/div>\n\n\n\n<ul class=\"wp-block-list\" id=\"indice\"><li><a href=\"#atual\"><strong>Situa\u00e7\u00e3o atual do concurso<\/strong><\/a><ul><li><a href=\"#retificacao\"><strong>Retifica\u00e7\u00e3o<\/strong><\/a><\/li><\/ul><ul><li><a href=\"#banca\"><strong>Banca organizadora<\/strong><\/a><\/li><li><a href=\"#comiss\u00e3o\"><strong>Comiss\u00e3o<\/strong><\/a><\/li><\/ul><\/li><li><a href=\"#carreira\"><strong>Carreira<\/strong><\/a><ul><li><a href=\"#cargo\"><strong>Cargos e Vagas<\/strong><\/a><\/li><li><a href=\"#requisito\"><strong>Requisitos<\/strong><\/a><\/li><li><a href=\"#atribui\u00e7\u00e3o\"><strong>Atribui\u00e7\u00f5es<\/strong><\/a><\/li><li><a href=\"#salario\"><strong>Sal\u00e1rios e Benef\u00edcios<\/strong><\/a><\/li><\/ul><\/li><li><a href=\"#etapas\"><strong>Etapas de provas<\/strong><\/a><\/li><li><a href=\"#\u00faltimo\"><strong>\u00daltimo Concurso<\/strong><\/a><\/li><li><a href=\"#cursos\"><strong>Cursos<\/strong><\/a><\/li><li><a href=\"#ficha\"><strong>Ficha T\u00e9cnica<\/strong><\/a><\/li><\/ul>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"atual\">Concurso COREN SE: situa\u00e7\u00e3o atual<\/h2>\n\n\n\n<ul class=\"has-background wp-block-list\" style=\"background-color:#a9d1ea\"><li><strong>Inscri\u00e7\u00f5es: <\/strong><s>18\/10 a 10\/11\/2021<\/s><\/li><li><strong>Taxa:<\/strong> R$ 74,50, para n\u00edvel superior e R$ 49,50 para n\u00edvel m\u00e9dio<\/li><li><strong>Prova:<\/strong> <s>12\/12\/2021<\/s><\/li><\/ul>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"resultados\">Resultados <\/h3>\n\n\n\n<ul class=\"wp-block-list\"><li>09 de mar\u00e7o de 2022- Divulgado a homologa\u00e7\u00e3o do resultado final do concurso COREN SE. <\/li><\/ul>\n\n\n\n<ul class=\"wp-block-list\"><li>04 de janeiro de 2022 &#8211; <b>P<\/b>ublicado o resultado final da prova objetiva. <a href=\"https:\/\/www.in.gov.br\/en\/web\/dou\/-\/edital-n-7\/coren-se-de-3-de-janeiro-de-2022-concurso-publico-para-o-provimento-de-vagas-em-cargos-de-enfermeiro-fiscal-e-de-tecnico-administrativo-371907735\" target=\"_blank\" rel=\"noreferrer noopener\">Confira aqui!<\/a>  <\/li><\/ul>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"retificacao\"><a href=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/10\/22170217\/retificacao_ii.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">Retifica\u00e7\u00e3o<\/a><\/h4>\n\n\n\n<p>Foram alterados os requisitos para os candidatos ao cargo de Enfermeiro Fiscal, que agora devem possuir diploma, devidamente registrado, de conclus\u00e3o de curso de gradua\u00e7\u00e3o em Enfermagem, carteira nacional de habilita\u00e7\u00e3o, no m\u00ednimo, do tipo &#8220;B&#8221;, registro definitivo de, no m\u00ednimo, 3 anos na respectiva categoria profissional e comprovada<br \/>experi\u00eancia profissional de, no m\u00ednimo, 3 anos.<\/p>\n\n\n\n<p>Os candidatos que se inscreveram e que n\u00e3o possu\u00edrem esses atributos poder\u00e3o solicitar a devolu\u00e7\u00e3o do valor pago como taxa de inscri\u00e7\u00e3o entre as <strong>10 horas do dia 6 e as 18 horas do dia 10 de dezembro de 2021<\/strong>, no endere\u00e7o eletr\u00f4nico do Cebraspe, devendo, para tanto, informar seu n\u00famero de inscri\u00e7\u00e3o e senha de acesso, seu CPF, dados banc\u00e1rios e dados referentes ao concurso. <\/p>\n\n\n\n<p>O prazo m\u00e1ximo para a devolu\u00e7\u00e3o da taxa de inscri\u00e7\u00e3o ser\u00e1 o dia 10 de fevereiro de 2022. O candidato que j\u00e1 tiver efetivado a inscri\u00e7\u00e3o e efetuado o pagamento do boleto banc\u00e1rio e que n\u00e3o solicitar a devolu\u00e7\u00e3o da taxa ser\u00e1 automaticamente considerado inscrito no concurso.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"banca\">Banca organizadora <\/h4>\n\n\n\n<p>O Centro Brasileiro de Pesquisa em Avalia\u00e7\u00e3o e Sele\u00e7\u00e3o e de Promo\u00e7\u00e3o de Eventos (Cebraspe)&nbsp;\u00e9 a banca organizadora do concurso COREN SE. O contrato firmado entre o Conselho e o Cebraspe foi feito na modalidade Dispensa de Licita\u00e7\u00e3o. <\/p>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"comiss\u00e3o\">Comiss\u00e3o<\/h4>\n\n\n\n<p>O COREN SE resolveu <a href=\"https:\/\/www.in.gov.br\/en\/web\/dou\/-\/portaria-n-94-de-2-de-outubro-de-2020-281544473\" target=\"_blank\" rel=\"noreferrer noopener\">alterar a Comiss\u00e3o<\/a> designada pela Portaria n\u00ba 277\/2019, publicada na se\u00e7\u00e3o 2 do Di\u00e1rio Oficial da Uni\u00e3o de 07 de janeiro de 2020, p\u00e1gina 61, para acompanhar a realiza\u00e7\u00e3o de Concurso P\u00fablico para provimento de empregos p\u00fablicos efetivos de T\u00e9cnico Administrativo e Enfermeiro Fiscal, composta pelos seguintes membros:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Clarice Fonseca Mandarino (Conselheira);<\/li><li>Lucas Fernandes Araujo (Empregado p\u00fablico do Coren-SE);<\/li><li>Daniela de Santana Miranda (Empregada p\u00fablica do Coren-SE);<\/li><li>Igor Fernando Acioly Silva Baima (Representante do SINDISCOSE); <\/li><li>Gabriela de Carvalho Lima Pereira (Representante do Sindicato dos Enfermeiros do Estado de Sergipe-SEESE).<\/li><li>Art. 2\u00b0 &#8211; A Conselheira Clarice Fonseca Mandarino ser\u00e1 a Presidente da Comiss\u00e3o.<\/li><\/ul>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"carreira\">Concurso COREN SE: carreira<\/h2>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"cargo\">Cargos e Vagas<\/h4>\n\n\n\n<figure class=\"wp-block-table is-style-stripes\"><table class=\"has-background\" style=\"background-color:#e7f5fe\"><tbody><tr><td class=\"has-text-align-center\" data-align=\"center\">CARGOS<\/td><td class=\"has-text-align-center\" data-align=\"center\">VAGAS<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">Enfermeiro Fiscal<\/td><td class=\"has-text-align-center\" data-align=\"center\">2<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">T\u00e9cnico Administrativo<\/td><td class=\"has-text-align-center\" data-align=\"center\">3<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"salario\">Sal\u00e1rios e Benef\u00edcios <\/h4>\n\n\n\n<p>Enfermeiro Fiscal &#8211; R$ 4.750,00<br \/>T\u00e9cnico Administrativo &#8211; R$ 1.307,42<br \/><\/p>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"requisito\">Requisitos <\/h4>\n\n\n\n<p>T\u00c9CNICO ADMINISTRATIVO <\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Ensino M\u00e9dio Completo<\/li><\/ul>\n\n\n\n<p>ENFERMEIRO FISCAL<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Ensino Superior Completo em Enfermagem; <\/li><li>Registro definitivo no COREN de, no m\u00ednimo, 3 anos; <\/li><li>Experi\u00eancia profissional de, no m\u00ednimo, 3 anos.<\/li><\/ul>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"atribui\u00e7\u00e3o\">Atribui\u00e7\u00f5es<\/h4>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"tecnico-administrativo\">T\u00e9cnico administrativo<\/h4>\n\n\n\n<ul class=\"wp-block-list\"><li>Executar servi\u00e7os de apoio nas diversas \u00e1reas administrativas e assessorias;<\/li><li>Organizar e controlar correspond\u00eancias, memorandos, of\u00edcios, circulares, processos e demais documentos relativos a sua \u00e1rea, visando a otimiza\u00e7\u00e3o do atendimento das necessidades de sua chefia imediata e das demais \u00e1reas;<\/li><li>Assistir a chefia imediata em assuntos de natureza administrativa e\/ou t\u00e9cnica, executando, controlando e acompanhando o desenvolvimento das tarefas em sua \u00e1rea;<\/li><li>Identificar necessidades de material, confer\u00eancia no recebimento, armazenamento e conserva\u00e7\u00e3o dos mesmos, mantendo atualizados os registros de estoque, assegurando o suprimento de materiais em sua \u00e1rea;<\/li><li>Otimizar o uso dos recursos dispon\u00edveis;<\/li><li>Fornecer apoio administrativo \u00e0s equipes, participando, sob orienta\u00e7\u00e3o, dos processos de execu\u00e7\u00e3o dos servi\u00e7os e atividades de sua \u00e1rea;<\/li><li>Organizar e zelar pelos diversos bens de sua unidade de trabalho, disponibilizados para a execu\u00e7\u00e3o das tarefas;<\/li><li>Prestar atendimento ao p\u00fablico das mais variadas maneiras, tais como: atendimento telef\u00f4nico, presencial, via e-mail, entre outros;<\/li><li>Redigir correspond\u00eancias, memorandos, of\u00edcios, relat\u00f3rios e outros trabalhos administrativos;<\/li><li>Organizar o arquivo de documentos recebidos e emitidos da \u00e1rea;<\/li><li>Elaborar tabelas, gr\u00e1ficos e programa\u00e7\u00e3o visual gr\u00e1fica e editora\u00e7\u00e3o de textos e imagens, sob supervis\u00e3o;<\/li><li>Pautar mat\u00e9rias, redigir artigos e assuntos referentes \u00e0 divulga\u00e7\u00e3o, sob supervis\u00e3o;<\/li><li>Registrar fotograficamente os eventos promovidos pelo Conselho e quando da participa\u00e7\u00e3o de conselheiros, quando solicitado. Enviar e receber malotes;<\/li><li>Protocolar e arquivar e distribuir correspond\u00eancias;<\/li><li>Verificar, montar, organizar e registrar processos, verificando os documentos necess\u00e1rios para sua composi\u00e7\u00e3o, numerando-os, visando controle e coer\u00eancia;<\/li><li>Requisitar servi\u00e7os de manuten\u00e7\u00e3o de m\u00f3veis, equipamentos,<br \/>m\u00e1quinas e instala\u00e7\u00f5es;<\/li><li>Oferecer suporte a processos licitat\u00f3rios com base nas diretrizes superiores, para aquisi\u00e7\u00e3o de materiais, equipamentos e servi\u00e7os;<\/li><li>Providenciar junto a ag\u00eancias de viagens a emiss\u00e3o e reserva de passagens, assim como reserva em hot\u00e9is;<\/li><li>Estimar pre\u00e7o junto a fornecedores, montando tabelas comparativas e relat\u00f3rios de apoio \u00e0 decis\u00e3o;<\/li><li>Exercer, sob supervis\u00e3o, atividades impress\u00e3o, grava\u00e7\u00e3o de fotolitos; realizar acabamentos diversos nos impressos do COFEN.<\/li><\/ul>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"enfermeiro-fiscal\">Enfermeiro fiscal<\/h4>\n\n\n\n<ul class=\"wp-block-list\"><li>Executar, nos locais de trabalho, as a\u00e7\u00f5es fiscalizat\u00f3rias do exerc\u00edcio da Enfermagem;<\/li><li>Realizar visitas de fiscaliza\u00e7\u00e3o na jurisdi\u00e7\u00e3o do COREN-SE, de acordo com o planejamento elaborado e\/ou n\u00e3o-programado, quando necess\u00e1rio;<\/li><li>Elaborar relat\u00f3rio ao t\u00e9rmino de cada visita fiscalizat\u00f3ria, com descri\u00e7\u00e3o das atividades realizadas;<\/li><li>Prestar orienta\u00e7\u00f5es aos profissionais de Enfermagem e aos dirigentes dos servi\u00e7os de sa\u00fade a respeito do COREN-SE, suas finalidades e suas atividades, no sentido de melhorar e aprimorar o atendimento de enfermagem \u00e0 comunidade, divulgando Leis, Decis\u00f5es, o C\u00f3digo de \u00c9tica e Resolu\u00e7\u00f5es;<\/li><li>Orientar os profissionais de Enfermagem quanto \u00e0 import\u00e2ncia da inscri\u00e7\u00e3o no COREN-SE e da compulsoriedade da anuidade;<\/li><li>Participar das reuni\u00f5es do COREN-SE quando convocado;<\/li><li>Realizar palestras e reuni\u00f5es de esclarecimentos na \u00e1rea de jurisdi\u00e7\u00e3o do COREN-SE, sempre que necess\u00e1rio;<\/li><li>Participar de comiss\u00f5es, quando solicitado;<\/li><li>Receber den\u00fancias e colher informa\u00e7\u00f5es necess\u00e1rias no sentido de avaliar a sua proced\u00eancia e encaminh\u00e1-las \u00e0 Chefia da Unidade;<\/li><li>Orientar o encaminhamento de den\u00fancias;<\/li><li>notificar e lavrar autos de infra\u00e7\u00e3o de ilegalidades e irregularidades;<\/li><li>Orientar quanto \u00e0 obrigatoriedade da Certid\u00e3o de Responsabilidade T\u00e9cnica, fornecendo requerimento pr\u00f3prio e demais documentos necess\u00e1rios;<\/li><li>Arquivar os documentos resultantes da fiscaliza\u00e7\u00e3o na pasta da institui\u00e7\u00e3o (de forma organizada);<\/li><li>Prestar orienta\u00e7\u00e3o aos Atendentes de Enfermagem e assemelhados, informando-os quanto \u00e0 obrigatoriedade da autoriza\u00e7\u00e3o de trabalho para esta categoria, fornecida pelo COREN-SE;<\/li><li>Participar de programas de divulga\u00e7\u00e3o do sistema COFEN\/Conselhos Regionais, do COREN-SE e do sistema de fiscaliza\u00e7\u00e3o;<\/li><li>Realizar ato fiscalizat\u00f3rio em institui\u00e7\u00f5es de ensino de n\u00edvel m\u00e9dio ou superior de Enfermagem, tendo em vista a legisla\u00e7\u00e3o de Enfermagem e as normas pertinentes \u00e0 educa\u00e7\u00e3o, em conson\u00e2ncia com as Secretarias de Educa\u00e7\u00e3o, MEC ou \u00f3rg\u00e3o equivalente;<\/li><li>Prestar informa\u00e7\u00f5es ao Plen\u00e1rio e \u00e0 Diretoria do COREN-SE, sempre que solicitado;<\/li><li>Orientar os profissionais de Enfermagem e os dirigentes das institui\u00e7\u00f5es de sa\u00fade a corrigirem espontaneamente irregularidades, porventura constatadas e, se necess\u00e1rio, lavrar notifica\u00e7\u00e3o e retornar para verificar se foram corrigidas;<\/li><li>Realizar visitas fiscalizat\u00f3rias n\u00e3o-programadas, que lhe sejam determinadas pelo Chefe da Unidade de Fiscaliza\u00e7\u00e3o e\/ou Diretoria;<\/li><li>Executar outras atividades correlatas, bem como aquelas que, por sua natureza, estejam inseridas no \u00e2mbito de suas atribui\u00e7\u00f5es.<\/li><\/ul>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"etapas\">Concurso COREN SE: Etapas de provas<\/h2>\n\n\n\n<p>A prova objetiva  foi de car\u00e1ter classificat\u00f3rio e eliminat\u00f3rio para ambos os cargos. Tamb\u00e9m estava previsto a prova de avalia\u00e7\u00e3o de t\u00edtulos para Enfermeiro Fiscal, essa fase foi apenas classificat\u00f3ria.<\/p>\n\n\n\n<p><strong>Enfermeiro Fiscal<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-table is-style-stripes\"><table class=\"has-background\" style=\"background-color:#e7f5fe\"><thead><tr><th class=\"has-text-align-center\" data-align=\"center\">PROVA<\/th><th class=\"has-text-align-center\" data-align=\"center\">TIPO \u00c1REA DE CONHECIMENTO<\/th><th class=\"has-text-align-center\" data-align=\"center\">N\u00daMERO DE QUEST\u00d5ES<\/th><th class=\"has-text-align-center\" data-align=\"center\">CAR\u00c1TER<\/th><\/tr><\/thead><tbody><tr><td class=\"has-text-align-center\" data-align=\"center\">(P1) Objetiva Conhecimentos gerais 30 Eliminat\u00f3rio e classificat\u00f3rio<\/td><td class=\"has-text-align-center\" data-align=\"center\">Conhecimentos gerais<\/td><td class=\"has-text-align-center\" data-align=\"center\">30<\/td><td class=\"has-text-align-center\" data-align=\"center\">Eliminat\u00f3rio e classificat\u00f3rio<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">(P2) Objetiva Conhecimentos espec\u00edficos 20<\/td><td class=\"has-text-align-center\" data-align=\"center\">Conhecimentos espec\u00edficos<\/td><td class=\"has-text-align-center\" data-align=\"center\">20<\/td><td class=\"has-text-align-center\" data-align=\"center\"><\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">(P3) Avalia\u00e7\u00e3o de t\u00edtulos<\/td><td class=\"has-text-align-center\" data-align=\"center\">\u2013<\/td><td class=\"has-text-align-center\" data-align=\"center\">\u2013<\/td><td class=\"has-text-align-center\" data-align=\"center\">(P3) Avalia\u00e7\u00e3o de t\u00edtulos \u2013 \u2013 Classificat\u00f3rio<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<p><strong>T\u00e9cnico Administrativo<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-table is-style-stripes\"><table class=\"has-background\" style=\"background-color:#fcf0ef\"><thead><tr><th class=\"has-text-align-center\" data-align=\"center\">PROVA<\/th><th class=\"has-text-align-center\" data-align=\"center\">TIPO \u00c1REA DE CONHECIMENTO<\/th><th class=\"has-text-align-center\" data-align=\"center\">N\u00daMERO DE QUEST\u00d5ES<\/th><th class=\"has-text-align-center\" data-align=\"center\">CAR\u00c1TER<\/th><\/tr><\/thead><tbody><tr><td class=\"has-text-align-center\" data-align=\"center\">(P1) Objetiva Conhecimentos gerais 30 Eliminat\u00f3rio e classificat\u00f3rio<\/td><td class=\"has-text-align-center\" data-align=\"center\">Conhecimentos gerais<\/td><td class=\"has-text-align-center\" data-align=\"center\">30<\/td><td class=\"has-text-align-center\" data-align=\"center\">Eliminat\u00f3rio e classificat\u00f3rio<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">(P2) Objetiva Conhecimentos espec\u00edficos 20<\/td><td class=\"has-text-align-center\" data-align=\"center\">Conhecimentos espec\u00edficos<\/td><td class=\"has-text-align-center\" data-align=\"center\">20<\/td><td class=\"has-text-align-center\" data-align=\"center\"><\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"prova-objetiva\">Prova objetiva<\/h2>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"disciplinas\">Disciplinas<\/h3>\n\n\n\n<p><strong>Conhecimentos B\u00e1sicos<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>L\u00edngua Portuguesa<\/li><li>\u00c9tica na Administra\u00e7\u00e3o P\u00fablica e Legisla\u00e7\u00e3o<\/li><li>No\u00e7\u00f5es de Direito Administrativo<\/li><li>No\u00e7\u00f5es de Inform\u00e1tica<\/li><li>Conhecimentos sobre estado de Sergipe<\/li><\/ul>\n\n\n\n<p><strong>Conhecimentos Espec\u00edficos<\/strong><\/p>\n\n\n\n<p>Para Enfermeiro, conhecimentos relativos \u00e0 enfermagem e legisla\u00e7\u00e3o espec\u00edfica.<\/p>\n\n\n\n<p>Para T\u00e9cnico Administrativo, conhecimentos relativos a assistente administrativo e legisla\u00e7\u00e3o espec\u00edfica.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"estrutura-da-prova\"><strong>Estrutura da prova<\/strong><\/h3>\n\n\n\n<p>As quest\u00f5es das provas objetivas foram do tipo m\u00faltipla escolha, com quatro op\u00e7\u00f5es (A, B, C e D), sendo uma \u00fanica resposta correta, de acordo com o comando da quest\u00e3o. Haver\u00e1, na folha de respostas, para cada quest\u00e3o, quatro campos de marca\u00e7\u00e3o: um campo para cada uma das quatro op\u00e7\u00f5es A, B, C e D, devendo o candidato preencher o campo correspondente \u00e0 resposta considerada por ele correta, de acordo com o comando da quest\u00e3o.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"avaliacao\">Avalia\u00e7\u00e3o de T\u00edtulos<\/h2>\n\n\n\n<figure class=\"wp-block-table is-style-stripes\"><table class=\"has-background\" style=\"background-color:#e9fbe5\"><thead><tr><th class=\"has-text-align-center\" data-align=\"center\">QUADRO DE ATRIBUI\u00c7\u00c3O DE PONTOS PARA A AVALIA\u00c7\u00c3O DE T\u00cdTULOS<\/th><\/tr><\/thead><tbody><tr><td class=\"has-text-align-center\" data-align=\"center\">AL\u00cdNEA<\/td><td class=\"has-text-align-center\" data-align=\"center\">T\u00cdTULO<\/td><td class=\"has-text-align-center\" data-align=\"center\">VALOR DE CADA T\u00cdTULO<\/td><td class=\"has-text-align-center\" data-align=\"center\">VALOR M\u00c1XIMO DOS T\u00cdTULOS<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">A<\/td><td class=\"has-text-align-center\" data-align=\"center\">incluir<\/td><td class=\"has-text-align-center\" data-align=\"center\">1,00<\/td><td class=\"has-text-align-center\" data-align=\"center\">1,00<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">B<\/td><td class=\"has-text-align-center\" data-align=\"center\">incluir<\/td><td class=\"has-text-align-center\" data-align=\"center\">0,70<\/td><td class=\"has-text-align-center\" data-align=\"center\">0,70<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">C<\/td><td class=\"has-text-align-center\" data-align=\"center\">incluir<\/td><td class=\"has-text-align-center\" data-align=\"center\">0,30<\/td><td class=\"has-text-align-center\" data-align=\"center\">0,60<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">D<\/td><td class=\"has-text-align-center\" data-align=\"center\">incluir<\/td><td class=\"has-text-align-center\" data-align=\"center\">0,10<\/td><td class=\"has-text-align-center\" data-align=\"center\">0,20<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">E<\/td><td class=\"has-text-align-center\" data-align=\"center\">incluir<\/td><td class=\"has-text-align-center\" data-align=\"center\">0,25 p\/ano completo, sem sobreposi\u00e7\u00e3o de tempo<\/td><td class=\"has-text-align-center\" data-align=\"center\">2,50<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\"><\/td><td class=\"has-text-align-center\" data-align=\"center\">TOTAL M\u00c1XIMO DE PONTOS<\/td><td class=\"has-text-align-center\" data-align=\"center\"><\/td><td class=\"has-text-align-center\" data-align=\"center\">5,00<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"\u00faltimo\">Concurso COREN SE: \u00daltimo concurso<\/h2>\n\n\n\n<p>O \u00faltimo concurso COREN SE aconteceu em 2010 e foi organizado pela banca Amiga P\u00fablica. Foram ofertadas 25 vagas no total, divididas entre: <\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>a) T\u00e9cnico Administrativo <\/li><li>b) T\u00e9cnico em contabilidade <\/li><li>c) T\u00e9cnico em Suporte <\/li><li>d) Advogado<\/li><li>e) Enfermeiro fiscal <\/li><\/ul>\n\n\n\n<h2 class=\"has-text-align-center wp-block-heading\" id=\"h-quer-saber-tudo-sobre-concursos-previstos-confira-nossos-artigos\">Quer saber tudo sobre concursos previstos?<br \/>Confira nossos artigos!<\/h2>\n\n\n\n<ul class=\"wp-block-list\"><li><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-abertos\/\" target=\"_blank\" rel=\"noreferrer noopener\">Concursos abertos<\/a><\/li><li><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-2021\/\" target=\"_blank\" rel=\"noreferrer noopener\">Concursos 2021<\/a><\/li><li><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-2022\/\" target=\"_blank\" rel=\"noreferrer noopener\">Concursos 2022<\/a><\/li><\/ul>\n\n\n\n<h2 class=\"has-text-align-center wp-block-heading\" id=\"cursos\"><strong><em>Quer estudar para o concurso Coren SE?<\/em><\/strong><\/h2>\n\n\n\n<p><em>Gostou desta oportunidade e deseja come\u00e7ar se preparar agora mesmo? Ent\u00e3o, confira os nossos cursos e comece a estudar:<\/em><\/p>\n\n\n\n<div class=\"col-sm\">\n      <div class=\"banner-estrategia\" id=\"box-assinatura\">\n        <h3 class=\"titulo-assinatura\">Cursos para COREN SE<\/h3>\n        <p class=\"subtitulo-assinatura\">Conhe\u00e7a os cursos<\/p>\n        <div class=\"box-botao\">\n          <a class=\"btn-assinatura\" target=\"_blank\" href=\"https:\/\/www.estrategiaconcursos.com.br\/cursosPorConcurso\/conselho-regional-de-enfermagem-de-sergipe-coren-se\/\" role=\"button\" rel=\"noopener noreferrer\">Conhe\u00e7a mais<\/a>\n        <\/div>\n      <\/div>\n      <p class=\"texto-auxiliar\">Prepare-se com o melhor material e com quem mais aprova em Concursos P\u00fablicos em todo o pa\u00eds.<\/p>\n    <\/div>\n\n\n\n<div class=\"container\" id=\"boxes\">\n  <div class=\"row\">\n    <div class=\"col-sm\">\n      <div class=\"estrategia\" id=\"box-assinatura\">\n        <h3 class=\"titulo-assinatura\">Assinatura Concursos<\/h3>\n        <p class=\"subtitulo-assinatura\">Assinatura de 1 ano ou 2 anos*<\/p>\n        <div class=\"box-botao\">\n          <a class=\"btn-assinatura\" target=\"_blank\" href=\"https:\/\/www.estrategiaconcursos.com.br\/assinaturas\/\" role=\"button\" rel=\"noopener noreferrer\">ASSINE AGORA<\/a>\n        <\/div>\n      <\/div>\n      <p class=\"texto-auxiliar\"><\/p>\n    <\/div>\n    <div class=\"col-sm\">\n      <div class=\"questoes\" id=\"box-assinatura\">\n        <h3 class=\"titulo-assinatura\">Sistema de Quest\u00f5es<\/h3>\n        <p class=\"subtitulo-assinatura\">Assinatura de 1 ano ou 2 anos\n<\/p>\n        <div class=\"box-botao\">\n          <a class=\"btn-assinatura\" target=\"_blank\" href=\"https:\/\/www.estrategiaconcursos.com.br\/cursosPorConcurso\/sistema-de-questoes\/#\/\" role=\"button\" rel=\"noopener noreferrer\">ASSINE AGORA<\/a>\n        <\/div>\n      <\/div>\n      <p class=\"texto-auxiliar\"><\/p>\n    <\/div>\n  <\/div>\n<\/div>\n\n\n\n<figure class=\"wp-block-image is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/04\/05154617\/ficha-tecnica-12-1024x632.png\" alt=\"O atributo alt desta imagem est\u00e1 vazio. O nome do arquivo \u00e9 ficha-tecnica-12-1024x632.png\" width=\"228\" height=\"141\"\/><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"ficha\"><strong>Informa\u00e7\u00f5es d<\/strong>o concurso <\/h3>\n\n\n\n<p>\u25ba<strong>Data prevista<\/strong>&nbsp;<b>da prova:&nbsp;<\/b><s>12\/12\/2021<\/s><br \/>\u25ba<strong>Vagas<\/strong>: 5<br \/>\u25ba<strong>Cargos<\/strong>: Enfermeiro Fiscal \/ T\u00e9cnico Administrativo<br \/>\u25ba<strong>Banca<\/strong>: Cebraspe<br \/>\u25ba<strong>Escolaridade<\/strong>: N\u00edvel M\u00e9dio e Superior<br \/>\u25ba<strong>Edital<\/strong>: <a href=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/02\/25091446\/coren-se-edital-1.pdf\">edital 2021<\/a><br \/><\/p>\n\n\n\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Foi publicado no Di\u00e1rio Oficial da Uni\u00e3o desta quarta-feira (09\/03), a homologa\u00e7\u00e3o do resultado final do concurso COREN SE (Conselho Regional de Enfermagem de Sergipe). Confira aqui se seu nome consta na lista de aprovados do concurso p\u00fablico do COREN SE. Concurso COREN SE Status:\u00a0resultado final homologado Vagas:\u00a05 Sal\u00e1rio inicial:\u00a0R$ 1.307,42 \/ R$ 4.750,00 Edital:\u00a0Edital [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":461344,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"post_tipo":"news_page","footnotes":""},"categories":[214992],"tags":[],"tax_estado":[219988],"class_list":["post-461293","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-concursos-administrativos","tax_estado-se"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.2 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Concurso COREN SE: homologado resultado final<\/title>\n<meta name=\"description\" content=\"Concurso COREN SE: veja o resultado final. S\u00e3o ofertadas vagas para T\u00e9cnico Administrativo e Enfermeiro Fiscal.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-coren-se\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Concurso COREN SE: homologado resultado final\" \/>\n<meta property=\"og:description\" content=\"Concurso COREN SE: veja o resultado final. S\u00e3o ofertadas vagas para T\u00e9cnico Administrativo e Enfermeiro Fiscal.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-coren-se\/\" \/>\n<meta property=\"og:site_name\" content=\"Estrat\u00e9gia Concursos\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/EstrategiaConcursos\" \/>\n<meta property=\"article:published_time\" content=\"2022-03-09T03:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-03-09T10:56:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2019\/12\/17115314\/COREN_SE.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"625\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Coordena\u00e7\u00e3o\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:site\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Coordena\u00e7\u00e3o\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"10 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-coren-se\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-coren-se\/\"},\"author\":{\"name\":\"Coordena\u00e7\u00e3o\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/b4a388c97673c5f483d72185668afa1f\"},\"headline\":\"Concurso COREN SE: homologado resultado final\",\"datePublished\":\"2022-03-09T03:00:00+00:00\",\"dateModified\":\"2022-03-09T10:56:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-coren-se\/\"},\"wordCount\":1849,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-coren-se\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2019\/12\/17115314\/COREN_SE.jpg\",\"articleSection\":[\"Executivo (Administrativa)\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-coren-se\/#respond\"]}],\"copyrightYear\":\"2022\",\"copyrightHolder\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-coren-se\/\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-coren-se\/\",\"name\":\"Concurso COREN SE: homologado resultado final\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-coren-se\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-coren-se\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2019\/12\/17115314\/COREN_SE.jpg\",\"datePublished\":\"2022-03-09T03:00:00+00:00\",\"dateModified\":\"2022-03-09T10:56:52+00:00\",\"description\":\"Concurso COREN SE: veja o resultado final. S\u00e3o ofertadas vagas para T\u00e9cnico Administrativo e Enfermeiro Fiscal.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-coren-se\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-coren-se\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-coren-se\/#primaryimage\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2019\/12\/17115314\/COREN_SE.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2019\/12\/17115314\/COREN_SE.jpg\",\"width\":1200,\"height\":625,\"caption\":\"concurso coren se\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-coren-se\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Concurso COREN SE: homologado resultado final\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"name\":\"Estrat\u00e9gia Concursos\",\"description\":\"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.\",\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\",\"name\":\"Estrat\u00e9gia Concursos\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"width\":230,\"height\":60,\"caption\":\"Estrat\u00e9gia Concursos\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/EstratConcursos\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/b4a388c97673c5f483d72185668afa1f\",\"name\":\"Coordena\u00e7\u00e3o\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/b720319e4c9a967eb58678d110f4fe35452fc5d5f97b202bac7b8acceb18c6ad?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/b720319e4c9a967eb58678d110f4fe35452fc5d5f97b202bac7b8acceb18c6ad?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/b720319e4c9a967eb58678d110f4fe35452fc5d5f97b202bac7b8acceb18c6ad?s=96&d=mm&r=g\",\"caption\":\"Coordena\u00e7\u00e3o\"},\"sameAs\":[\"https:\/\/www.facebook.com\/EstrategiaConcursos\",\"https:\/\/x.com\/EstratConcursos\"],\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/estrategia2013\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Concurso COREN SE: homologado resultado final","description":"Concurso COREN SE: veja o resultado final. S\u00e3o ofertadas vagas para T\u00e9cnico Administrativo e Enfermeiro Fiscal.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-coren-se\/","og_locale":"pt_BR","og_type":"article","og_title":"Concurso COREN SE: homologado resultado final","og_description":"Concurso COREN SE: veja o resultado final. S\u00e3o ofertadas vagas para T\u00e9cnico Administrativo e Enfermeiro Fiscal.","og_url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-coren-se\/","og_site_name":"Estrat\u00e9gia Concursos","article_author":"https:\/\/www.facebook.com\/EstrategiaConcursos","article_published_time":"2022-03-09T03:00:00+00:00","article_modified_time":"2022-03-09T10:56:52+00:00","og_image":[{"width":1200,"height":625,"url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2019\/12\/17115314\/COREN_SE.jpg","type":"image\/jpeg"}],"author":"Coordena\u00e7\u00e3o","twitter_card":"summary_large_image","twitter_creator":"@EstratConcursos","twitter_site":"@EstratConcursos","twitter_misc":{"Escrito por":"Coordena\u00e7\u00e3o","Est. tempo de leitura":"10 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-coren-se\/#article","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-coren-se\/"},"author":{"name":"Coordena\u00e7\u00e3o","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/b4a388c97673c5f483d72185668afa1f"},"headline":"Concurso COREN SE: homologado resultado final","datePublished":"2022-03-09T03:00:00+00:00","dateModified":"2022-03-09T10:56:52+00:00","mainEntityOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-coren-se\/"},"wordCount":1849,"commentCount":0,"publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-coren-se\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2019\/12\/17115314\/COREN_SE.jpg","articleSection":["Executivo (Administrativa)"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-coren-se\/#respond"]}],"copyrightYear":"2022","copyrightHolder":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-coren-se\/","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-coren-se\/","name":"Concurso COREN SE: homologado resultado final","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-coren-se\/#primaryimage"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-coren-se\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2019\/12\/17115314\/COREN_SE.jpg","datePublished":"2022-03-09T03:00:00+00:00","dateModified":"2022-03-09T10:56:52+00:00","description":"Concurso COREN SE: veja o resultado final. S\u00e3o ofertadas vagas para T\u00e9cnico Administrativo e Enfermeiro Fiscal.","breadcrumb":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-coren-se\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-coren-se\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-coren-se\/#primaryimage","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2019\/12\/17115314\/COREN_SE.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2019\/12\/17115314\/COREN_SE.jpg","width":1200,"height":625,"caption":"concurso coren se"},{"@type":"BreadcrumbList","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-coren-se\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.estrategiaconcursos.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Concurso COREN SE: homologado resultado final"}]},{"@type":"WebSite","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","name":"Estrat\u00e9gia Concursos","description":"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.","publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization","name":"Estrat\u00e9gia Concursos","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","width":230,"height":60,"caption":"Estrat\u00e9gia Concursos"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/EstratConcursos"]},{"@type":"Person","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/b4a388c97673c5f483d72185668afa1f","name":"Coordena\u00e7\u00e3o","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/b720319e4c9a967eb58678d110f4fe35452fc5d5f97b202bac7b8acceb18c6ad?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b720319e4c9a967eb58678d110f4fe35452fc5d5f97b202bac7b8acceb18c6ad?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b720319e4c9a967eb58678d110f4fe35452fc5d5f97b202bac7b8acceb18c6ad?s=96&d=mm&r=g","caption":"Coordena\u00e7\u00e3o"},"sameAs":["https:\/\/www.facebook.com\/EstrategiaConcursos","https:\/\/x.com\/EstratConcursos"],"url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/estrategia2013\/"}]}},"_links":{"self":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/461293","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/comments?post=461293"}],"version-history":[{"count":98,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/461293\/revisions"}],"predecessor-version":[{"id":983425,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/461293\/revisions\/983425"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media\/461344"}],"wp:attachment":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media?parent=461293"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/categories?post=461293"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tags?post=461293"},{"taxonomy":"tax_estado","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tax_estado?post=461293"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}