{"id":46088,"date":"2016-08-11T01:11:37","date_gmt":"2016-08-11T04:11:37","guid":{"rendered":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?p=46088"},"modified":"2016-08-11T01:11:37","modified_gmt":"2016-08-11T04:11:37","slug":"provas-de-direito-tributario-comentadas-tce-pa","status":"publish","type":"post","link":"https:\/\/www.estrategiaconcursos.com.br\/blog\/provas-de-direito-tributario-comentadas-tce-pa\/","title":{"rendered":"Provas de Direito Tribut\u00e1rio Comentadas &#8211; TCE-PA"},"content":{"rendered":"<p>Ol\u00e1, pessoal, tudo bem?<\/p>\n<p>No concurso para <strong>Auditor de Controle Externo do Tribunal de Contas do Estado do Par\u00e1<\/strong> (TCE-PA), foi cobrada a disciplina de Direito Tribut\u00e1rio, nos seguintes cargos:<\/p>\n<p><strong>Cargo 2:<\/strong> Auditor de Controle Externo \u2013 A\u0301rea: Procuradoria<\/p>\n<p><strong>Cargo 7:<\/strong> Auditor de Controle Externo \u2013 A\u0301rea: Administrativa \u2013 Especialidade: Direito<\/p>\n<p><strong>Cargo 26:<\/strong> Auditor de Controle Externo \u2013 A\u0301rea: Fiscalizac\u0327a\u0303o \u2013 Especialidade: Direito<\/p>\n<p>Com a recente publica\u00e7\u00e3o dos gabaritos provis\u00f3rios, comentamos todas as quest\u00f5es cobradas da nossa disciplina nessas provas!<\/p>\n<p>N\u00e3o vislumbramos poss\u00edveis recursos nas quest\u00f5es de Direito Tribut\u00e1rio.<\/p>\n<p>Os coment\u00e1rios seguem abaixo.<\/p>\n<p>Desejo muito sucesso a todos voc\u00eas!<\/p>\n<p>Um abra\u00e7o e boa sorte!<\/p>\n<p>Prof. F\u00e1bio Dutra<\/p>\n<hr \/>\n<p><span style=\"color: #ff0000\"><strong>Cargo 2: Auditor de Controle Externo \u2013 A\u0301rea: Procuradoria<\/strong><\/span><\/p>\n<hr \/>\n<p>Com base nas normas gerais e constitucionais de direito tribut\u00e1rio, julgue os itens que se seguem.<\/p>\n<p><strong>89<\/strong> A concess\u00e3o de parcelamento tribut\u00e1rio n\u00e3o d\u00e1 ensejo \u00e0 extin\u00e7\u00e3o dos cr\u00e9ditos tribut\u00e1rios parcelados, pois n\u00e3o ocorre o fen\u00f4meno da nova\u00e7\u00e3o.<\/p>\n<p><strong>Coment\u00e1rio: <\/strong>Primeiramente, h\u00e1 que se entender que nova\u00e7\u00e3o significa a substitui\u00e7\u00e3o da nova obriga\u00e7\u00e3o (parcelamento), extinguindo a obriga\u00e7\u00e3o anterior (cr\u00e9dito tribut\u00e1rio). Isso n\u00e3o ocorre, como afirma a quest\u00e3o, j\u00e1 que, durante o parcelamento, o cr\u00e9dito tribut\u00e1rio subsiste, por\u00e9m permanece com sua exigibilidade suspensa, nos termos do art. 151, VI, do CTN. Quest\u00e3o correta.<\/p>\n<hr \/>\n<p><strong>90<\/strong> Situa\u00e7\u00e3o hipot\u00e9tica: Mesmo ocorrendo o fato gerador de obriga\u00e7\u00e3o tribut\u00e1ria, o Estado, por meio de lei, exclui a possibilidade de se exigir o pagamento do cr\u00e9dito tribut\u00e1rio relativo a tal obriga\u00e7\u00e3o.<\/p>\n<p><strong>Assertiva:<\/strong> Essa situa\u00e7\u00e3o configura hip\u00f3tese de isen\u00e7\u00e3o de tributo.<\/p>\n<p><strong>Coment\u00e1rio: <\/strong>De fato, a isen\u00e7\u00e3o consiste na dispensa legal do pagamento do tributo devido. Ainda que o fato gerador ocorra, o cr\u00e9dito tribut\u00e1rio \u00e9 exclu\u00eddo, nos termos do art. 175, I, do CTN. Quest\u00e3o correta.<\/p>\n<hr \/>\n<p><strong>91<\/strong> O princ\u00edpio da legalidade tribut\u00e1ria impede tanto o aumento como a cria\u00e7\u00e3o de qualquer tributo, sen\u00e3o por meio de lei.<\/p>\n<p><strong>Coment\u00e1rio: <\/strong>O princ\u00edpio da legalidade impede a cria\u00e7\u00e3o de qualquer tributo, sen\u00e3o por meio de lei. Contudo, quanto \u00e0 majora\u00e7\u00e3o dos tributos, h\u00e1 determinadas exce\u00e7\u00f5es previstas na Constitui\u00e7\u00e3o Federal. Portanto, esta quest\u00e3o est\u00e1 errada.<\/p>\n<hr \/>\n<p><strong>92<\/strong> Situa\u00e7\u00e3o hipot\u00e9tica: Elza foi notificada em 28\/3\/2016 a pagar imposto que tinha sido objeto de processo ent\u00e3o transitado em julgado. Ap\u00f3s o tr\u00e2nsito em julgado do processo, adveio lei que excluiu dos fatos geradores da exa\u00e7\u00e3o a situa\u00e7\u00e3o discutida.<\/p>\n<p><strong>Assertiva:<\/strong> Nessa situa\u00e7\u00e3o, Elza tem direito de n\u00e3o pagar o imposto.<\/p>\n<p><strong>Coment\u00e1rio: <\/strong>A norma que concede isen\u00e7\u00e3o s\u00f3 produz efeitos quanto aos fatos geradores ocorridos a partir da vig\u00eancia desta lei. Portanto, Elza tem a obriga\u00e7\u00e3o de pagar o imposto. Quest\u00e3o errada.<\/p>\n<hr \/>\n<p><strong>93<\/strong> Situa\u00e7\u00e3o hipot\u00e9tica: O invent\u00e1rio de determinado contribuinte nascido em S\u00e3o Lu\u00eds e residente em Manaus que faleceu em S\u00e3o Paulo foi aberto em Belo Horizonte. De seu invent\u00e1rio faz parte um im\u00f3vel situado em Salvador. <strong>Assertiva:<\/strong> Nesse caso, o imposto sobre heran\u00e7as e doa\u00e7\u00f5es referente a esse im\u00f3vel deve ser pago em Belo Horizonte.<\/p>\n<p><strong>Coment\u00e1rio: <\/strong>Conforme preceitua o art. 155, \u00a7 1\u00ba, I, da CF\/88, o ITCMD compete ao Estado da situa\u00e7\u00e3o do bem im\u00f3vel, ou ao Distrito Federal. Consequentemente, o imposto \u00e9 devido ao Estado da Bahia, j\u00e1 que o im\u00f3vel est\u00e1 situado em Salvador. Quest\u00e3o errada.<\/p>\n<hr \/>\n<p><strong>94<\/strong> A constitui\u00e7\u00e3o de um cr\u00e9dito tribut\u00e1rio pode ser ato unilateral da administra\u00e7\u00e3o p\u00fablica, bem como pode depender de declara\u00e7\u00e3o do contribuinte.<\/p>\n<p><strong>Coment\u00e1rio: <\/strong>Realmente, a constitui\u00e7\u00e3o do cr\u00e9dito tribut\u00e1rio pode se resumir em ato unilateral da administra\u00e7\u00e3o p\u00fablica, dispensando qualquer participa\u00e7\u00e3o do sujeito passivo, mas tamb\u00e9m pode depender diretamente da declara\u00e7\u00e3o do contribuinte, como ocorre no lan\u00e7amento por declara\u00e7\u00e3o e tamb\u00e9m no lan\u00e7amento por homologa\u00e7\u00e3o. Quest\u00e3o errada.<\/p>\n<hr \/>\n<p><span style=\"color: #ff0000\"><strong>Cargo 7: Auditor de Controle Externo \u2013 A\u0301rea: Administrativa \u2013 Especialidade: Direito<\/strong><\/span><\/p>\n<hr \/>\n<p>Em uma federa\u00e7\u00e3o como a brasileira, em que mesmo os munic\u00edpios t\u00eam esfera pr\u00f3pria de atribui\u00e7\u00f5es exercidas com autonomia, a Constitui\u00e7\u00e3o trata do provimento de recursos aos v\u00e1rios entes pol\u00edticos \u2014 no caso brasileiro, a Uni\u00e3o, os estados, o Distrito Federal e os munic\u00edpios \u2014, a fim de que cada qual possa atender aos respectivos disp\u00eandios.<\/p>\n<p><em>Luciano Amaro. Direito tribut\u00e1rio brasileiro. 21.\u00aa ed. S\u00e3o Paulo: Saraiva, 2016, p. 115 (com adapta\u00e7\u00f5es).<\/em><\/p>\n<p>Tendo como refer\u00eancia inicial o texto apresentado, julgue os itens a seguir, em rela\u00e7\u00e3o \u00e0 discrimina\u00e7\u00e3o constitucional de rendas.<\/p>\n<p><strong>\u00a0<\/strong><strong>89<\/strong> A institui\u00e7\u00e3o, pela Uni\u00e3o, da Contribui\u00e7\u00e3o Provis\u00f3ria sobre Movimenta\u00e7\u00e3o Financeira (CPMF) decorre do exerc\u00edcio de sua compet\u00eancia residual. Para a sua institui\u00e7\u00e3o, exige-se a edi\u00e7\u00e3o de emenda constitucional, uma vez que a hip\u00f3tese de incid\u00eancia desse tipo de contribui\u00e7\u00e3o n\u00e3o encontra previs\u00e3o na Constitui\u00e7\u00e3o Federal de 1988.<\/p>\n<p><strong>Coment\u00e1rio:<\/strong> O exerc\u00edcio da compet\u00eancia residual da Uni\u00e3o, relativamente \u00e0s contribui\u00e7\u00f5es residuais, deve ser realizado por meio de lei complementar, o que n\u00e3o ocorreu no caso da CPMF, institu\u00edda pela Lei 9.311\/96. Ocorre que, neste caso, a referida lei foi institu\u00edda \u00e0 luz da EC 12\/1996, que incluiu o art. 74 ao ADCT. Quest\u00e3o errada.<\/p>\n<hr \/>\n<p><strong>90<\/strong> O produto arrecadado pela Uni\u00e3o proveniente do imposto de renda \u00e9 partilhado com os estados e munic\u00edpios de forma indireta, por meio da institui\u00e7\u00e3o de fundos, qualificando-se como direito subjetivo dos entes federativos beneficiados.<\/p>\n<p><strong>Coment\u00e1rio: <\/strong>Embora seja qualificado como direito subjetivo dos entes federativos beneficiados pela reparti\u00e7\u00e3o constitucional de receitas tribut\u00e1rias, n\u00e3o \u00e9 todo o produto arrecadado pela Uni\u00e3o proveniente do imposto de renda que \u00e9 partilhado com os Estados e Munic\u00edpios de forma indireta. A CF\/88 prev\u00ea que ser\u00e1 repartido apenas 49% do produto do IR, exclu\u00eddo deste montante o produto da arrecada\u00e7\u00e3o do imposto da Uni\u00e3o sobre renda e proventos de qualquer natureza, incidente na fonte, sobre rendimentos pagos, a qualquer t\u00edtulo, pelos Estados, Distrito Federal e Munic\u00edpios, suas autarquias e pelas funda\u00e7\u00f5es que institu\u00edrem e mantiverem, que ser\u00e1 repartido diretamente com eles. Quest\u00e3o errada.<\/p>\n<hr \/>\n<p><strong>91<\/strong> A Constitui\u00e7\u00e3o Federal de 1988 adotou o modelo de federalismo cooperativo, de modo que a autonomia financeira dos entes federativos \u00e9 assegurada pela atribui\u00e7\u00e3o de compet\u00eancias tribut\u00e1rias e participa\u00e7\u00e3o nas receitas tribut\u00e1rias arrecadadas de tributos de compet\u00eancia de outros entes.<\/p>\n<p><strong>Coment\u00e1rio:<\/strong> Realmente, ao adotar o modelo de federalismo cooperativo, a CF\/88 distribuiu compet\u00eancias tribut\u00e1rias a todos os entes federados, para que instituam seus pr\u00f3prios tributos, al\u00e9m de tamb\u00e9m ter garantido participa\u00e7\u00e3o nas receitas tribut\u00e1rias arrecadadas de tributos de compet\u00eancia de outros entes. Dessa forma, buscou-se assegurar a autonomia financeira dos entes federados. Quest\u00e3o correta.<\/p>\n<hr \/>\n<p>Em rela\u00e7\u00e3o \u00e0s limita\u00e7\u00f5es constitucionais ao poder de tributar e \u00e0 atual jurisprud\u00eancia do Supremo Tribunal Federal, julgue os itens seguintes.<\/p>\n<p><strong>\u00a0<\/strong><strong>92<\/strong> Qualificado como garantia individual do contribuinte e, por conseguinte, como cl\u00e1usula p\u00e9trea da Constitui\u00e7\u00e3o Federal de 1988, o princ\u00edpio da anterioridade n\u00e3o se aplica \u00e0 norma jur\u00eddica que altera o prazo de recolhimento da obriga\u00e7\u00e3o tribut\u00e1ria.<\/p>\n<p><strong>Coment\u00e1rio:<\/strong> \u00c9 a jurisprud\u00eancia pac\u00edfica do STF, qualificando o princ\u00edpio da anterioridade como garantia individual do contribuinte. A S\u00famula Vinculante 50 prev\u00ea que Norma legal que altera o prazo de recolhimento de obriga\u00e7\u00e3o tribut\u00e1ria n\u00e3o se sujeita ao princ\u00edpio da anterioridade. Quest\u00e3o correta.<\/p>\n<hr \/>\n<p><strong>93<\/strong> A imunidade das entidades de assist\u00eancia social sem fins lucrativos abrange seu patrim\u00f4nio, sua renda e seus servi\u00e7os. Assim, n\u00e3o incide o imposto sobre a propriedade predial e territorial urbana sobre im\u00f3vel de sua propriedade alugado a terceiros, ainda que os alugu\u00e9is n\u00e3o sejam revertidos a sua finalidade essencial.<\/p>\n<p><strong>Coment\u00e1rio:<\/strong> De acordo com a S\u00famula Vinculante 52 do STF, \u00a0ainda quando alugado a terceiros, permanece imune ao IPTU o im\u00f3vel pertencente a qualquer das entidades referidas pelo art. 150, VI, \u201cc\u201d (que se aplica \u00e0s entidades de assist\u00eancia social sem fins lucrativos), da Constitui\u00e7\u00e3o Federal, desde que o valor dos alugu\u00e9is seja aplicado nas atividades para as quais tais entidades foram constitu\u00eddas. Quest\u00e3o errada.<\/p>\n<hr \/>\n<p>No que concerne ao ICMS e \u00e0s disposi\u00e7\u00f5es constitucionais pertinentes \u00e0 concess\u00e3o de exonera\u00e7\u00f5es fiscais, julgue o item subsecutivo.<\/p>\n<p><strong>94<\/strong> A concess\u00e3o de isen\u00e7\u00f5es, incentivos e benef\u00edcios fiscais pelos estados depende de pr\u00e9via aprova\u00e7\u00e3o de conv\u00eanio interestadual, o que abrange a concess\u00e3o de diferimento no pagamento de d\u00e9bitos de imposto sobre opera\u00e7\u00f5es relativas \u00e0 circula\u00e7\u00e3o de mercadorias e presta\u00e7\u00e3o de servi\u00e7o de transporte interestadual e intermunicipal e de comunica\u00e7\u00e3o, ainda que inexista redu\u00e7\u00e3o do valor devido.<\/p>\n<p><strong>Coment\u00e1rio:<\/strong> De acordo com o art. 155, \u00a7 2\u00ba, XII, \u201cg\u201d, da CF\/88, a concess\u00e3o de isen\u00e7\u00f5es, incentivos e benef\u00edcios fiscais pelos estados depende de pr\u00e9via aprova\u00e7\u00e3o de conv\u00eanios interestaduais, que ser\u00e3o regulados por lei complementar. Contudo, o diferimento no pagamento de d\u00e9bitos do ICMS n\u00e3o se confunde com benef\u00edcio fiscal, n\u00e3o se aplicando a referida regra. Quest\u00e3o errada.<\/p>\n<hr \/>\n<p><span style=\"color: #ff0000\"><strong>Cargo 26: Auditor de Controle Externo \u2013 A\u0301rea: Fiscalizac\u0327a\u0303o \u2013 Especialidade: Direito<\/strong><\/span><\/p>\n<hr \/>\n<p>A sociedade empres\u00e1ria XYZ, que tem por objeto social o com\u00e9rcio de roupas e acess\u00f3rios, encontra estabelecida em Bel\u00e9m \u2013 PA. No desenvolvimento de sua atividade empresarial, essa pessoa jur\u00eddica prestava as declara\u00e7\u00f5es exigidas pela legisla\u00e7\u00e3o tribut\u00e1ria relativamente ao imposto sobre opera\u00e7\u00f5es relativas<\/p>\n<p>\u00e0 circula\u00e7\u00e3o de mercadorias e presta\u00e7\u00e3o de servi\u00e7o de transporte interestadual e intermunicipal e de comunica\u00e7\u00e3o (ICMS) e efetuava o pagamento antecipado do cr\u00e9dito tribut\u00e1rio. A partir de dezembro de 2011, embora a sociedade empres\u00e1ria tenha continuado a enviar as declara\u00e7\u00f5es, deixou de efetuar o pagamento do valor correspondente \u00e0 obriga\u00e7\u00e3o principal. Em fevereiro de 2016, a secretaria de fazenda estadual identificou, mediante fiscaliza\u00e7\u00e3o no estabelecimento empresarial, o descumprimento das obriga\u00e7\u00f5es principal e acess\u00f3rias relativas ao pagamento do ICMS, tais como a emiss\u00e3o de notas fiscais e preenchimento de livro fiscal obrigat\u00f3rio.<\/p>\n<p>A respeito dessa situa\u00e7\u00e3o hipot\u00e9tica, julgue os itens seguintes.<\/p>\n<p><strong>89 <\/strong>O descumprimento de obriga\u00e7\u00e3o de emiss\u00e3o de nota fiscal d\u00e1 ensejo \u00e0 realiza\u00e7\u00e3o, pelo poder p\u00fablico, do lan\u00e7amento de of\u00edcio, para fins de aplica\u00e7\u00e3o da penalidade cab\u00edvel. Nesse caso, a multa aplicada equipara-se ao cr\u00e9dito decorrente da obriga\u00e7\u00e3o principal, em virtude da sua natureza jur\u00eddica de obriga\u00e7\u00e3o de dar.<\/p>\n<p><strong>Coment\u00e1rio:<\/strong> De acordo com o art. 113, \u00a7 3\u00ba, do CTN, a obriga\u00e7\u00e3o acess\u00f3ria, pelo simples fato da sua inobserv\u00e2ncia, converte-se em obriga\u00e7\u00e3o principal relativamente \u00e0 penalidade pecuni\u00e1ria.<\/p>\n<p>Dessa forma, ao descumprir a obriga\u00e7\u00e3o de emitir notas fiscais (obriga\u00e7\u00e3o acess\u00f3ria), a empresa fica sujeita ao lan\u00e7amento de of\u00edcio de multa, constituindo o cr\u00e9dito tribut\u00e1rio, j\u00e1 que a penalidade pecuni\u00e1ria tamb\u00e9m \u00e9 uma obriga\u00e7\u00e3o tribut\u00e1ria principal. Quest\u00e3o correta.<\/p>\n<hr \/>\n<p><strong>90<\/strong> Se, antes de qualquer ato de verifica\u00e7\u00e3o da declara\u00e7\u00e3o enviada pela administra\u00e7\u00e3o tribut\u00e1ria, a pessoa jur\u00eddica identificar que uma das declara\u00e7\u00f5es de ICMS constituiu o cr\u00e9dito tribut\u00e1rio em valor menor que o devido e, em seguida, retificar a declara\u00e7\u00e3o anterior e realizar o pagamento integral, estar\u00e1\u00a0caracterizada a den\u00fancia espont\u00e2nea, afastando-se a aplica\u00e7\u00e3o de penalidade.<\/p>\n<p><strong>Coment\u00e1rio:<\/strong> A den\u00fancia espont\u00e2nea s\u00f3 estar\u00e1 caracterizada se, al\u00e9m do pagamento integral do ICMS devido, o sujeito passivo pagar tamb\u00e9m os juros de mora devidos, por ocasi\u00e3o do atraso no recolhimento. Quest\u00e3o errada.<\/p>\n<hr \/>\n<p><strong>91<\/strong> A declara\u00e7\u00e3o de ICMS realizada pelo contribuinte constitui o cr\u00e9dito tribut\u00e1rio, de modo que n\u00e3o h\u00e1 a necessidade de realiza\u00e7\u00e3o do ato de lan\u00e7amento por homologa\u00e7\u00e3o, iniciando-se o prazo prescricional desde o transcurso do prazo de vencimento da obriga\u00e7\u00e3o principal.<\/p>\n<p><strong>Coment\u00e1rio: <\/strong>De acordo com a S\u00famula 436, do STJ, a entrega de declara\u00e7\u00e3o pelo contribuinte reconhecendo d\u00e9bito fiscal constitui o cr\u00e9dito tribut\u00e1rio, dispensada qualquer outra provid\u00eancia por parte do fisco. Quest\u00e3o correta.<\/p>\n<hr \/>\n<p>Em rela\u00e7\u00e3o \u00e0s limita\u00e7\u00f5es constitucionais ao poder de tributar, julgue o pr\u00f3ximo item.<\/p>\n<p><strong>92<\/strong> Conforme o entendimento do Supremo Tribunal Federal, a imunidade rec\u00edproca \u00e9 extensiva \u00e0s sociedades de economia mista e empresas p\u00fablicas que prestam servi\u00e7os p\u00fablicos essenciais e obrigat\u00f3rios, ainda que remunerados por tarifas, desde que n\u00e3o haja apropria\u00e7\u00e3o privada dos lucros obtidos com a atividade p\u00fablica, preservando-se, assim, o patrim\u00f4nio, a renda e os servi\u00e7os vinculados \u00e0s suas finalidades essenciais.<\/p>\n<p><strong>Coment\u00e1rio: <\/strong>Realmente, o STF tem concedido interpreta\u00e7\u00e3o ampla \u00e0 imunidade rec\u00edproca, decidindo que tamb\u00e9m as sociedades de economia mista e empresas p\u00fablicas que prestam servi\u00e7os p\u00fablicos essenciais e obrigat\u00f3rios encontram-se imunes, mesmo em se tratando de servi\u00e7os remunerados por tarifas, com a condi\u00e7\u00e3o de que o patrim\u00f4nio, a renda e os servi\u00e7os vinculados \u00e0s suas finalidades essenciais. Quest\u00e3o correta.<\/p>\n<hr \/>\n<p>Julgue os itens subsequentes, relativos ao imposto sobre servi\u00e7os de qualquer natureza (ISSQN) e \u00e0 certid\u00e3o negativa.<\/p>\n<p><strong>93<\/strong> A administra\u00e7\u00e3o tribut\u00e1ria poder\u00e1 fornecer certid\u00e3o positiva com os mesmos efeitos da certid\u00e3o negativa na hip\u00f3tese de cr\u00e9ditos tribut\u00e1rios com exigibilidade suspensa ou de cr\u00e9ditos objeto de execu\u00e7\u00e3o fiscal garantidos por penhora.<\/p>\n<p><strong>Coment\u00e1rio: <\/strong>\u00c9 o que estabelece o art. 206, do CTN: tem os mesmos efeitos previstos no artigo anterior a certid\u00e3o de que conste a exist\u00eancia de cr\u00e9ditos n\u00e3o vencidos, em curso de cobran\u00e7a executiva em que tenha sido efetivada a penhora, ou cuja exigibilidade esteja suspensa. Portanto, nas hip\u00f3teses citadas na quest\u00e3o, \u00e9 poss\u00edvel a emiss\u00e3o de certid\u00e3o positiva com os mesmos efeitos da certid\u00e3o negativa. Quest\u00e3o correta.<\/p>\n<hr \/>\n<p><strong>94<\/strong> O aspecto material da hip\u00f3tese de incid\u00eancia de ISSQN consiste na presta\u00e7\u00e3o de servi\u00e7os, conceito jur\u00eddico de direito privado que indica uma obriga\u00e7\u00e3o de fazer a favor de terceiros mediante remunera\u00e7\u00e3o, de modo que abrange a atividade de loca\u00e7\u00e3o de bens m\u00f3veis.<\/p>\n<p><strong>Coment\u00e1rio: <\/strong>N\u00e3o obstante a correta defini\u00e7\u00e3o do aspecto material da hip\u00f3tese de incid\u00eancia do ISS, a jurisprud\u00eancia do STF j\u00e1 se encontra pacificada no sentido de que a atividade de loca\u00e7\u00e3o de bens m\u00f3veis n\u00e3o caracteriza presta\u00e7\u00e3o de servi\u00e7os, n\u00e3o incidindo ISS sobre tal opera\u00e7\u00e3o. Quest\u00e3o errada.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ol\u00e1, pessoal, tudo bem? No concurso para Auditor de Controle Externo do Tribunal de Contas do Estado do Par\u00e1 (TCE-PA), foi cobrada a disciplina de Direito Tribut\u00e1rio, nos seguintes cargos: Cargo 2: Auditor de Controle Externo \u2013 A\u0301rea: Procuradoria Cargo 7: Auditor de Controle Externo \u2013 A\u0301rea: Administrativa \u2013 Especialidade: Direito Cargo 26: Auditor de [&hellip;]<\/p>\n","protected":false},"author":150,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"post_tipo":"article","footnotes":""},"categories":[],"tags":[1368,1369],"tax_estado":[],"class_list":["post-46088","post","type-post","status-publish","format-standard","hentry","tag-concurso-tce-pa","tag-tce-pa"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.2 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Provas de Direito Tribut\u00e1rio Comentadas - TCE-PA<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/provas-de-direito-tributario-comentadas-tce-pa\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Provas de Direito Tribut\u00e1rio Comentadas - TCE-PA\" \/>\n<meta property=\"og:description\" content=\"Ol\u00e1, pessoal, tudo bem? No concurso para Auditor de Controle Externo do Tribunal de Contas do Estado do Par\u00e1 (TCE-PA), foi cobrada a disciplina de Direito Tribut\u00e1rio, nos seguintes cargos: Cargo 2: Auditor de Controle Externo \u2013 A\u0301rea: Procuradoria Cargo 7: Auditor de Controle Externo \u2013 A\u0301rea: Administrativa \u2013 Especialidade: Direito Cargo 26: Auditor de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/provas-de-direito-tributario-comentadas-tce-pa\/\" \/>\n<meta property=\"og:site_name\" content=\"Estrat\u00e9gia Concursos\" \/>\n<meta property=\"article:published_time\" content=\"2016-08-11T04:11:37+00:00\" \/>\n<meta name=\"author\" content=\"F\u00e1bio Dutra\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:site\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"F\u00e1bio Dutra\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"12 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/provas-de-direito-tributario-comentadas-tce-pa\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/provas-de-direito-tributario-comentadas-tce-pa\/\"},\"author\":{\"name\":\"F\u00e1bio Dutra\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/c6615b1e72eae70edca73ea5362ead63\"},\"headline\":\"Provas de Direito Tribut\u00e1rio Comentadas &#8211; TCE-PA\",\"datePublished\":\"2016-08-11T04:11:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/provas-de-direito-tributario-comentadas-tce-pa\/\"},\"wordCount\":2495,\"commentCount\":5,\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"keywords\":[\"concurso TCE PA\",\"TCE PA\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/provas-de-direito-tributario-comentadas-tce-pa\/#respond\"]}],\"copyrightYear\":\"2016\",\"copyrightHolder\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/provas-de-direito-tributario-comentadas-tce-pa\/\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/provas-de-direito-tributario-comentadas-tce-pa\/\",\"name\":\"Provas de Direito Tribut\u00e1rio Comentadas - TCE-PA\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\"},\"datePublished\":\"2016-08-11T04:11:37+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/provas-de-direito-tributario-comentadas-tce-pa\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/provas-de-direito-tributario-comentadas-tce-pa\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/provas-de-direito-tributario-comentadas-tce-pa\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Provas de Direito Tribut\u00e1rio Comentadas &#8211; TCE-PA\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"name\":\"Estrat\u00e9gia Concursos\",\"description\":\"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.\",\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\",\"name\":\"Estrat\u00e9gia Concursos\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"width\":230,\"height\":60,\"caption\":\"Estrat\u00e9gia Concursos\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/EstratConcursos\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/c6615b1e72eae70edca73ea5362ead63\",\"name\":\"F\u00e1bio Dutra\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/2fb4b2715a33320653086a45a7174528e6836e078753b587b59cb70f7b453819?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/2fb4b2715a33320653086a45a7174528e6836e078753b587b59cb70f7b453819?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/2fb4b2715a33320653086a45a7174528e6836e078753b587b59cb70f7b453819?s=96&d=mm&r=g\",\"caption\":\"F\u00e1bio Dutra\"},\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/fabiodutraestrategiaconcursos-com-br\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Provas de Direito Tribut\u00e1rio Comentadas - TCE-PA","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.estrategiaconcursos.com.br\/blog\/provas-de-direito-tributario-comentadas-tce-pa\/","og_locale":"pt_BR","og_type":"article","og_title":"Provas de Direito Tribut\u00e1rio Comentadas - TCE-PA","og_description":"Ol\u00e1, pessoal, tudo bem? No concurso para Auditor de Controle Externo do Tribunal de Contas do Estado do Par\u00e1 (TCE-PA), foi cobrada a disciplina de Direito Tribut\u00e1rio, nos seguintes cargos: Cargo 2: Auditor de Controle Externo \u2013 A\u0301rea: Procuradoria Cargo 7: Auditor de Controle Externo \u2013 A\u0301rea: Administrativa \u2013 Especialidade: Direito Cargo 26: Auditor de [&hellip;]","og_url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/provas-de-direito-tributario-comentadas-tce-pa\/","og_site_name":"Estrat\u00e9gia Concursos","article_published_time":"2016-08-11T04:11:37+00:00","author":"F\u00e1bio Dutra","twitter_card":"summary_large_image","twitter_creator":"@EstratConcursos","twitter_site":"@EstratConcursos","twitter_misc":{"Escrito por":"F\u00e1bio Dutra","Est. tempo de leitura":"12 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/provas-de-direito-tributario-comentadas-tce-pa\/#article","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/provas-de-direito-tributario-comentadas-tce-pa\/"},"author":{"name":"F\u00e1bio Dutra","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/c6615b1e72eae70edca73ea5362ead63"},"headline":"Provas de Direito Tribut\u00e1rio Comentadas &#8211; TCE-PA","datePublished":"2016-08-11T04:11:37+00:00","mainEntityOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/provas-de-direito-tributario-comentadas-tce-pa\/"},"wordCount":2495,"commentCount":5,"publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"keywords":["concurso TCE PA","TCE PA"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/provas-de-direito-tributario-comentadas-tce-pa\/#respond"]}],"copyrightYear":"2016","copyrightHolder":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/provas-de-direito-tributario-comentadas-tce-pa\/","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/provas-de-direito-tributario-comentadas-tce-pa\/","name":"Provas de Direito Tribut\u00e1rio Comentadas - TCE-PA","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website"},"datePublished":"2016-08-11T04:11:37+00:00","breadcrumb":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/provas-de-direito-tributario-comentadas-tce-pa\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/provas-de-direito-tributario-comentadas-tce-pa\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/provas-de-direito-tributario-comentadas-tce-pa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.estrategiaconcursos.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Provas de Direito Tribut\u00e1rio Comentadas &#8211; TCE-PA"}]},{"@type":"WebSite","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","name":"Estrat\u00e9gia Concursos","description":"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.","publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization","name":"Estrat\u00e9gia Concursos","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","width":230,"height":60,"caption":"Estrat\u00e9gia Concursos"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/EstratConcursos"]},{"@type":"Person","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/c6615b1e72eae70edca73ea5362ead63","name":"F\u00e1bio Dutra","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/2fb4b2715a33320653086a45a7174528e6836e078753b587b59cb70f7b453819?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2fb4b2715a33320653086a45a7174528e6836e078753b587b59cb70f7b453819?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2fb4b2715a33320653086a45a7174528e6836e078753b587b59cb70f7b453819?s=96&d=mm&r=g","caption":"F\u00e1bio Dutra"},"url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/fabiodutraestrategiaconcursos-com-br\/"}]}},"_links":{"self":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/46088","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/users\/150"}],"replies":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/comments?post=46088"}],"version-history":[{"count":3,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/46088\/revisions"}],"predecessor-version":[{"id":46092,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/46088\/revisions\/46092"}],"wp:attachment":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media?parent=46088"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/categories?post=46088"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tags?post=46088"},{"taxonomy":"tax_estado","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tax_estado?post=46088"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}