{"id":45030,"date":"2016-08-02T13:30:02","date_gmt":"2016-08-02T16:30:02","guid":{"rendered":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?p=45030"},"modified":"2016-08-02T13:49:07","modified_gmt":"2016-08-02T16:49:07","slug":"comentarios-prova-de-direitos-humanos-pm-pa","status":"publish","type":"post","link":"https:\/\/www.estrategiaconcursos.com.br\/blog\/comentarios-prova-de-direitos-humanos-pm-pa\/","title":{"rendered":"Coment\u00e1rios \u00e0 prova de Direitos Humanos PM-PA"},"content":{"rendered":"<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-45034\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2016\/08\/02132903\/PMPA.jpg\" alt=\"PMPA\" width=\"180\" height=\"180\" srcset=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2016\/08\/02132903\/PMPA.jpg 180w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2016\/08\/02132903\/PMPA.jpg 150w\" sizes=\"auto, (max-width: 180px) 100vw, 180px\" \/>A banca FADESP divulgou \u00a0a prova e o gabarito preliminares do concurso para os cargos de oficial e pra\u00e7a da Pol\u00edcia Militar do Estado do Par\u00e1. Neste artigo vamos analisar as quest\u00f5es de Direitos Humanos.<\/p>\n<p style=\"text-align: justify;\">Tivemos 5 quest\u00f5es para o cargo de oficial e outras 2 quest\u00f5es para o cargo de soldado. Tal como era esperado, a banca explorou assuntos gerais, tudo dentro do edital. A banca cobrou diretamente os dois principais diplomas da mat\u00e9ria: Declara\u00e7\u00e3o Universal dos Direitos Humanos (DUDH) e Conven\u00e7\u00e3o Americana de Direitos Humanos (Pacto de San Jos\u00e9 da Costa Rica).<\/p>\n<p style=\"text-align: justify;\">&#8212;<\/p>\n<p style=\"text-align: justify;\">Vamos come\u00e7ar com as quest\u00f5es do cargo e Oficial!<\/p>\n<h3 style=\"text-align: justify;\"><strong>Quest\u00e3o \u2013 FADESP\/PM-PA \u2013 Oficial &#8211; 2016<\/strong><\/h3>\n<p style=\"text-align: justify;\">A Declara\u00e7\u00e3o Universal dos Direitos Humanos \u00e9 um dos documentos mais importantes que inauguram a fase da internacionaliza\u00e7\u00e3o dos direitos humanos. Sobre a Declara\u00e7\u00e3o Universal dos<\/p>\n<p style=\"text-align: justify;\">Direitos Humanos, \u00e9 correto afirmar que<\/p>\n<p style=\"text-align: justify;\">(A) sua aprova\u00e7\u00e3o, em 10 de dezembro de 1948, pela Comiss\u00e3o de Direitos Humanos da Organiza\u00e7\u00e3o das Na\u00e7\u00f5es Unidas, trata-se de uma resposta aos horrores ocorridos na segunda guerra mundial.<\/p>\n<p style=\"text-align: justify;\">(B) seu conte\u00fado versa igualmente sobre direitos civis e pol\u00edticos e ainda sobre direitos econ\u00f4micos, sociais e culturais.<\/p>\n<p style=\"text-align: justify;\">(C) sua aprova\u00e7\u00e3o foi feita por todos os Estados-membros da Organiza\u00e7\u00e3o das Na\u00e7\u00f5es Unidas, possibilitando a instala\u00e7\u00e3o de um \u00f3rg\u00e3o internacional respons\u00e1vel por monitorar seu cumprimento.<\/p>\n<p style=\"text-align: justify;\">(D) seu conte\u00fado influenciou outras normas, como a Declara\u00e7\u00e3o Americana de Direitos e Deveres do Homem.<\/p>\n<h3 style=\"text-align: justify;\">Coment\u00e1rios<\/h3>\n<p style=\"text-align: justify;\">A <strong>alternativa A<\/strong> est\u00e1 incorreta. A DUDH constitui uma resolu\u00e7\u00e3o, que foi aprovada pela Assembleia Geral da ONU e n\u00e3o pela Comiss\u00e3o de Direitos Humanos.<\/p>\n<p style=\"text-align: justify;\">A <strong>alternativa B<\/strong> est\u00e1 correta e \u00e9 o gabarito da quest\u00e3o. \u00c9 sempre importante saber que a DUDH abrange essencialmente as duas primeiras dimens\u00f5es de direitos humanos: a) direitos civis e pol\u00edticos; e b) direitos sociais, econ\u00f4micos e culturais. Em rela\u00e7\u00e3o aos direitos difusos e coletivos (como o direito ambiental) eles s\u00e3o mencionados brevemente.<\/p>\n<p style=\"text-align: justify;\">A <strong>alternativa C<\/strong> est\u00e1 incorreta, pois como a DUDH foi aprovada como resolu\u00e7\u00e3o, formalmente ela n\u00e3o se apresenta como um tratado internacional, pelo que n\u00e3o cont\u00e9m instrumentos voltados \u00e0 exigibilidade dos seus direitos. Apenas com a edi\u00e7\u00e3o dos Pactos (Pacto Internacional dos Direitos Civis e Pol\u00edticos e Pacto Internacional dos Direitos Sociais, Econ\u00f4micos e Culturais) \u00e9 que temos a defesa dos direitos da DUDH de modo formal. Dito de outra forma, o PIDCP e PIDSEC explicitam os direitos declarados na DUDH, formando o que a doutrina denominada de <em>Bill of Rights<\/em>.<\/p>\n<p style=\"text-align: justify;\">A <strong>alternativa D <\/strong>est\u00e1 incorreta. Tanto a Declara\u00e7\u00e3o Americana dos Direitos e Deveres do Homem como a DUDH foram aprovadas no mesmo ano, em 1948. Apenas para que voc\u00ea tenha ideia, a Declara\u00e7\u00e3o Americana dos Direitos e Deveres do Homem foi aprovada em abril de 1948, ao passo que a DUDH foi aprovada em dezembro do referido ano.<\/p>\n<h3 style=\"text-align: justify;\">Quest\u00e3o \u2013 FADESP\/PM-PA \u2013 Oficial &#8211; 2016<\/h3>\n<p style=\"text-align: justify;\">O Pacto de S\u00e3o Jos\u00e9 da Costa Rica corresponde a um tratado internacional aprovado na Organiza\u00e7\u00e3o dos Estados Americanos. Sobre o Pacto de S\u00e3o Jos\u00e9 da Costa Rica, que recebe a designa\u00e7\u00e3o origin\u00e1ria de Conven\u00e7\u00e3o Americana de Direitos Humanos, \u00e9 correto afirmar que<\/p>\n<p style=\"text-align: justify;\">(A) o tratado estabelece, no seu artigo 1.1, a cl\u00e1usula geral de obriga\u00e7\u00f5es, que determina de forma expressa as obriga\u00e7\u00f5es de garantir e de respeitar os direitos humanos.<\/p>\n<p style=\"text-align: justify;\">(B) os direitos econ\u00f4micos, sociais e culturais possuem diversos dispositivos enunciativos, tal qual os direitos civis e pol\u00edticos.<\/p>\n<p style=\"text-align: justify;\">(C) todo Estado-membro da Organiza\u00e7\u00e3o dos Estados Americanos torna-se obrigatoriamente signat\u00e1rio da Conven\u00e7\u00e3o Americana de Direitos Humanos.<\/p>\n<p style=\"text-align: justify;\">(D) entrou em vigor em 1978, quando o Estado da Argentina depositou o instrumento de ratifica\u00e7\u00e3o junto \u00e0 Secretaria Geral da Organiza\u00e7\u00e3o dos Estados Americanos.<\/p>\n<h3 style=\"text-align: justify;\">Coment\u00e1rios<\/h3>\n<p style=\"text-align: justify;\">A <strong>alternativa A<\/strong> est\u00e1 correta e \u00e9 o gabarito da quest\u00e3o. Vejamos o art. 1\u00ba, do Pacto.<\/p>\n<p style=\"text-align: justify; padding-left: 30px;\">Artigo 1\u00ba &#8211; Obriga\u00e7\u00e3o de respeitar os direitos<\/p>\n<p style=\"text-align: justify; padding-left: 30px;\">Os Estados-partes nesta Conven\u00e7\u00e3o <strong>comprometem-se a respeitar os direitos e liberdades nela reconhecidos e a garantir seu livre e pleno exerc\u00edcio a toda pessoa que esteja sujeita \u00e0 sua jurisdi\u00e7\u00e3o<\/strong>, sem discrimina\u00e7\u00e3o alguma, por motivo de ra\u00e7a, cor, sexo, idioma, religi\u00e3o, opini\u00f5es pol\u00edticas ou de qualquer outra natureza, origem nacional ou social, posi\u00e7\u00e3o econ\u00f4mica, nascimento ou qualquer outra condi\u00e7\u00e3o social.<\/p>\n<p style=\"text-align: justify;\">A <strong>alternativa B<\/strong> est\u00e1 incorreta. Os direitos econ\u00f4micos, sociais e culturais s\u00e3o tratados no Protocolo de San Salvador e n\u00e3o no Pacto San Jos\u00e9 da Costa Rica. Apenas para frisar, os direitos de primeira dimens\u00e3o \u2013 direitos civis e pol\u00edticos \u2013 s\u00e3o tratados sim pela Conven\u00e7\u00e3o Americana de Direitos Humanos.<\/p>\n<p style=\"text-align: justify;\">A <strong>alternativa C<\/strong> est\u00e1 incorreta. Como o Pacto San Jos\u00e9 da Costa Rica \u00e9 um tratado ele deve ser ratificado pelos Estados para ter validade e a ratifica\u00e7\u00e3o de um documento internacional jamais ser\u00e1 compuls\u00f3ria, devido a soberania de cada Estado.<\/p>\n<p style=\"text-align: justify;\">A <strong>alternativa D<\/strong> est\u00e1 incorreta, pois a Argentina efetuou o dep\u00f3sito no ano de 1984. Esse tipo de quest\u00e3o, infelizmente, n\u00e3o mede conhecimento algum e constitui uma maldade da banca. De todo modo, a Argentina foi um dos \u00faltimos pa\u00edses a efetuar o dep\u00f3sito da Conven\u00e7\u00e3o e ainda fez reserva a parte do texto convencionado.<\/p>\n<h3 style=\"text-align: justify;\">Quest\u00e3o \u2013 FADESP\/PM-PA \u2013 Oficial &#8211; 2016<\/h3>\n<p style=\"text-align: justify;\">O Pacto de S\u00e3o Jos\u00e9 da Costa Rica cria o Sistema Interamericano de Prote\u00e7\u00e3o dos Direitos Humanos e estabelece as fun\u00e7\u00f5es da Corte Interamericana de Direitos Humanos. Sobre esse tribunal internacional, pode-se afirmar que<\/p>\n<p style=\"text-align: justify;\">(A) tem sede em S\u00e3o Jos\u00e9 na Costa Rica e, embora n\u00e3o seja permanente, seus ju\u00edzes est\u00e3o \u00e0 disposi\u00e7\u00e3o para participar dos per\u00edodos de sess\u00f5es.<\/p>\n<p style=\"text-align: justify;\">(B) suas senten\u00e7as s\u00e3o pass\u00edveis de apela\u00e7\u00e3o ou outro tipo de recurso para a Corte Internacional de Justi\u00e7a, conhecida como Corte de Haia.<\/p>\n<p style=\"text-align: justify;\">(C) poder\u00e1 exigir a restaura\u00e7\u00e3o do direito violado, mas n\u00e3o o pagamento de uma indeniza\u00e7\u00e3o, por se tratar de uma corte internacional de direitos humanos.<\/p>\n<p style=\"text-align: justify;\">(D) a Corte Interamericana de Direitos Humanos poder\u00e1 adotar medidas provis\u00f3rias, a fim de evitar danos irrepar\u00e1veis, desde que solicitadas no in\u00edcio da demanda judicial.<\/p>\n<h3 style=\"text-align: justify;\">Coment\u00e1rios<\/h3>\n<p style=\"text-align: justify;\">A <strong>alternativa A<\/strong> est\u00e1 correta e \u00e9 o gabarito da quest\u00e3o. A sede da Corte Interamericana de Direitos Humanos \u00e9 em San Jos\u00e9, onde foi editado o Pacto. De fato, a corte n\u00e3o \u00e9 permanente, mas os Ju\u00edzes devem estar presentes nas sess\u00f5es.<\/p>\n<p style=\"text-align: justify;\">A <strong>alternativa B<\/strong> est\u00e1 incorreta, n\u00e3o havendo se falar em recursos contra decis\u00f5es proferidas pela Corte Interamericana de Justi\u00e7a, ainda mais para \u00f3rg\u00e3o de outro sistema. Veja! A Corte Interamericana de Justi\u00e7a \u00e9 \u00f3rg\u00e3o judicante do Sistema Regional, ao passo que a Corte Internacional \u00e9 o \u00f3rg\u00e3o judicante do Sistema Global. Ambos possuem compet\u00eancia material e territorial distintas.<\/p>\n<p style=\"text-align: justify;\">A <strong>alternativa C<\/strong> est\u00e1 incorreta, pois o direito \u00e0 indeniza\u00e7\u00e3o est\u00e1 expressamente previsto no Pacto de Jose da Costa Rica. Veja o art. 63, 1:<\/p>\n<p style=\"text-align: justify;\">Quando decidir que houve viola\u00e7\u00e3o de um direito ou liberdade protegidos nesta Conven\u00e7\u00e3o, a Corte determinar\u00e1 que se assegure ao prejudicado o gozo do seu direito ou liberdade violados. Determinar\u00e1 tamb\u00e9m, se isso for procedente, que sejam reparadas as consequ\u00eancias da medida ou situa\u00e7\u00e3o que haja configurado a viola\u00e7\u00e3o desses direitos, bem como o pagamento de indeniza\u00e7\u00e3o justa \u00e0 parte lesada.<\/p>\n<p style=\"text-align: justify;\">Finalmente, a <strong>alternativa D<\/strong> est\u00e1 incorreta por contrariar a regra constante do art. 63, 2, do Pacto de San Jos\u00e9 da Costa Rica. Est\u00e1 correta a parte que se refere \u00e0 tomada de medidas provis\u00f3rias apenas quando necess\u00e1rio para evitar danos irrepar\u00e1veis \u00e0s pessoas. Veja, entretanto, que o dispositivo refere que essas medidas podem ser adotadas \u201cnos assuntos que estiver conhecendo\u201d, dando a entender que poder\u00e1 conced\u00ea-las no curso do processo perante a Corte.<\/p>\n<p style=\"text-align: justify;\">Em casos de extrema gravidade e urg\u00eancia, e quando se fizer necess\u00e1rio evitar danos irrepar\u00e1veis \u00e0s pessoas, a Corte, nos assuntos de que estiver conhecendo, poder\u00e1 tomar as medidas provis\u00f3rias que considerar pertinentes. Se se tratar de assuntos que ainda n\u00e3o estiverem submetidos ao seu conhecimento, poder\u00e1 atuar a pedido da Comiss\u00e3o.<\/p>\n<h3 style=\"text-align: justify;\">Quest\u00e3o \u2013 FADESP\/PM-PA \u2013 Oficial &#8211; 2016<\/h3>\n<p style=\"text-align: justify;\">A Comiss\u00e3o Interamericana de Direitos Humanos \u00e9 o \u00f3rg\u00e3o da Organiza\u00e7\u00e3o dos Estados Americanos especializado em mat\u00e9ria de Direitos Humanos, cujas atribui\u00e7\u00f5es tamb\u00e9m s\u00e3o definidas pelo Pacto de S\u00e3o Jos\u00e9 da Costa Rica. Sobre a Comiss\u00e3o Interamericana de Direitos Humanos, \u00e9 correto afirmar que<\/p>\n<p style=\"text-align: justify;\">(A) tem sede em S\u00e3o Jos\u00e9 na Costa Rica.<\/p>\n<p style=\"text-align: justify;\">(B) \u00e9 composta por membros com not\u00f3rio conhecimento na mat\u00e9ria de direitos humanos, n\u00e3o havendo a obrigatoriedade de que sejam da \u00e1rea jur\u00eddica.<\/p>\n<p style=\"text-align: justify;\">(C) tem como principal atribui\u00e7\u00e3o processar den\u00fancias individuais, bem como monitorar o cumprimento das obriga\u00e7\u00f5es decorrentes da Conven\u00e7\u00e3o Americana de Direitos Humanos, exercendo fun\u00e7\u00e3o judicial.<\/p>\n<p style=\"text-align: justify;\">(D) tem compet\u00eancia para receber e processar peti\u00e7\u00f5es individuais, mas n\u00e3o comunica\u00e7\u00f5es interestatais, as quais s\u00e3o de compet\u00eancia da Corte Interamericana de Direitos Humanos.<\/p>\n<h3 style=\"text-align: justify;\">Coment\u00e1rios<\/h3>\n<p style=\"text-align: justify;\">A <strong>alternativa A<\/strong> est\u00e1 incorreta. A sede da Comiss\u00e3o Interamericana de Direitos Humanos \u00e9 em Washington, nos Estados Unidos. Cuide para n\u00e3o confundir com a Corte Interamericana que possui sede em San Jose.<\/p>\n<p style=\"text-align: justify;\">A <strong>alternativa B<\/strong> est\u00e1 correta e \u00e9 o gabarito da quest\u00e3o. N\u00e3o h\u00e1 nenhum requisito de que os membros da Comiss\u00e3o devam ter forma\u00e7\u00e3o jur\u00eddica. Vejamos o art. 34, do Pacto San Jos\u00e9 da Costa Rica.<\/p>\n<p style=\"padding-left: 30px; text-align: justify;\">Artigo 34 &#8211; A Comiss\u00e3o Interamericana de Direitos Humanos compor-se-\u00e1 de sete membros, que dever\u00e3o ser pessoas de alta autoridade moral e de reconhecido saber em mat\u00e9ria de direitos humanos.<\/p>\n<p style=\"text-align: justify;\">A <strong>alternativa C<\/strong> est\u00e1 incorreta. A Comiss\u00e3o n\u00e3o possui fun\u00e7\u00e3o judicial, mas sim a Corte. A fun\u00e7\u00e3o da Comiss\u00e3o \u00e9 executiva! Nesse contexto, ela det\u00e9m a prerrogativa de processar den\u00fancia, monitorar o cumprimento das obriga\u00e7\u00f5es e, inclusive, poder\u00e1 ingressar com demanda judicial perante a Corte. Mas, n\u00e3o exercer fun\u00e7\u00e3o judicial, t\u00edpica de um tribunal.<\/p>\n<p style=\"text-align: justify;\">A <strong>alternativa D<\/strong> est\u00e1 incorreta, pois \u00e9 de compet\u00eancia da Comiss\u00e3o analisar as comunica\u00e7\u00f5es. Vejamos o art. 45, do Pacto.<\/p>\n<p style=\"text-align: justify; padding-left: 30px;\">Artigo 45 &#8211; 1. Todo Estado-parte pode, no momento do dep\u00f3sito do seu instrumento de ratifica\u00e7\u00e3o desta Conven\u00e7\u00e3o, ou de ades\u00e3o a ela, ou em qualquer momento posterior, declarar que reconhece a compet\u00eancia da Comiss\u00e3o para receber e examinar as comunica\u00e7\u00f5es em que um Estado-parte alegue haver outro Estado-parte incorrido em viola\u00e7\u00f5es dos direitos humanos estabelecidos nesta Conven\u00e7\u00e3o.<\/p>\n<h3 style=\"text-align: justify;\">Quest\u00e3o \u2013 FADESP\/PM-PA \u2013 Oficial &#8211; 2016<\/h3>\n<p style=\"text-align: justify;\">A luta pela vig\u00eancia dos Direitos Humanos e o embate pol\u00edtico-diplom\u00e1tico, travado nos organismos internacionais, consolida e acrescenta a normatiza\u00e7\u00e3o de direitos que surgem para atender necessidades humanas, dando significado ao Direito Internacional e aos Direitos Humanos. Sobre essa fase do Direito Internacional e dos Direitos Humanos, tem-se a afirmar que<\/p>\n<p style=\"text-align: justify;\">(A) um novo sentido para a prote\u00e7\u00e3o internacional dos Direitos Humanos foi iniciado com os Pactos Internacionais de Direitos Civis e Pol\u00edticos e de Direitos Econ\u00f4micos, Sociais e Culturais, aprovados em 1948, juntamente com a Declara\u00e7\u00e3o Universal dos Direitos Humanos.<\/p>\n<p style=\"text-align: justify;\">(B) o Direito Internacional e os Direitos Humanos visam fazer com que o Estado-parte de um determinado tratado assegure o conte\u00fado dos seus dispositivos. Assim, seus nacionais e qualquer indiv\u00edduo sob a sua jurisdi\u00e7\u00e3o podem acionar as inst\u00e2ncias competentes, devendo os sistemas internacionais ter car\u00e1ter subsidi\u00e1rio e complementar.<\/p>\n<p style=\"text-align: justify;\">(C) o Direito Internacional e os Direitos Humanos passam a estabelecer que o n\u00e3o cumprimento das obriga\u00e7\u00f5es previstas nos tratados internacionais de direitos humanos implica em possibilidade de san\u00e7\u00f5es internacionais, como embargo econ\u00f4mico.<\/p>\n<p style=\"text-align: justify;\">(D) os sistemas internacionais de prote\u00e7\u00e3o dos direitos humanos, que s\u00e3o inaugurados nessa fase, visam proteger os direitos dos indiv\u00edduos, mas somente podem ser acionados pelos Estados.<\/p>\n<h3 style=\"text-align: justify;\">Coment\u00e1rios<\/h3>\n<p style=\"text-align: justify;\">Veja cada uma das alternativas.<\/p>\n<p style=\"text-align: justify;\">A <strong>alternativa A<\/strong> est\u00e1 incorreta, pois a DUDH foi aprovada em 1948, j\u00e1 os Pactos Internacionais foram aprovados no ano de 1966.<\/p>\n<p style=\"text-align: justify;\">A <strong>alternativa B<\/strong> est\u00e1 correta e \u00e9 o gabarito da quest\u00e3o. Para voc\u00ea n\u00e3o errar essa alternativa, voc\u00ea deve compreender a sutileza do entendimento. Veja, o <strong>objetivo<\/strong> do Direito Internacional dos Direitos Humanos \u00e9 justamente esse, o de criar um mecanismo por interm\u00e9dio do qual as pessoas possam cobrar das inst\u00e2ncias competentes internas (e at\u00e9 mesmo internacionais) a observ\u00e2ncia das regras disciplinas nos tratados assumido.<\/p>\n<p style=\"text-align: justify;\">Pergunta-se:<\/p>\n<p style=\"text-align: justify;\">Isso ocorre na pr\u00e1tica?<\/p>\n<p style=\"text-align: justify;\">N\u00e3o, seja porque em alguns sistemas de Direitos Humanos n\u00e3o permitem que as pessoas peticionem diretamente \u00e0s Cortes Internacionais.<\/p>\n<p style=\"text-align: justify;\">De toda forma, a pretens\u00e3o dos Direitos Humanos \u00e9 justamente o que foi trazido na quest\u00e3o, pelo que a alternativa est\u00e1 correta.<\/p>\n<p style=\"text-align: justify;\">A <strong>alternativa C<\/strong> est\u00e1 incorreta, n\u00e3o havendo tal possibilidade de reprimenda pelo n\u00e3o cumprimento das regas internacionais de Direitos Humanos. Entre as possibilidades temos coa\u00e7\u00e3o moral do Estado e a indeniza\u00e7\u00e3o pecuni\u00e1ria.<\/p>\n<p style=\"text-align: justify;\">Por fim, a <strong>alternativa D<\/strong> est\u00e1 incorreta, pois temos situa\u00e7\u00f5es em que os pr\u00f3prios indiv\u00edduos podem acionar diretamente as Cortes internacionais. No caso do Sistema Europeu de Direitos Humanos existe tal prerrogativa. No que diz respeito ao Sistema Americano de Direitos Humanos, excepcionalmente, em caso de urg\u00eancia, \u00e9 poss\u00edvel que uma pessoa f\u00edsica ou at\u00e9 mesmo um grupo de pessoas ingresse diretamente na Corte Interamericana.<\/p>\n<p style=\"text-align: justify;\">&#8212;<\/p>\n<p style=\"text-align: justify;\">Na sequ\u00eancia, confira as 2 quest\u00f5es cobradas na prova de pra\u00e7as.<\/p>\n<h3 style=\"text-align: justify;\">Quest\u00e3o \u2013 FADESP\/PM-PA \u2013 Pra\u00e7a &#8211; 2016<\/h3>\n<p style=\"text-align: justify;\">O Pacto de S\u00e3o Jos\u00e9 da Costa Rica, tamb\u00e9m conhecido como Conven\u00e7\u00e3o Americana de Direitos Humanos, cria o chamado Sistema Interamericano de Prote\u00e7\u00e3o dos Direitos Humanos. Sobre isso, pode-se afirmar que<\/p>\n<p style=\"text-align: justify;\">(A) determina que os \u00f3rg\u00e3os de monitoramento do cumprimento das obriga\u00e7\u00f5es contidas s\u00e3o a Comiss\u00e3o Interamericana de Direitos Humanos, a Corte Interamericana de Direitos Humanos e a Secretaria-Geral da Organiza\u00e7\u00e3o dos Estados Americanos.<\/p>\n<p style=\"text-align: justify;\">(B) do Sistema Interamericano de Prote\u00e7\u00e3o dos Direitos Humanos fazem parte todos os Estados-membros da Organiza\u00e7\u00e3o dos Estados Americanos.<\/p>\n<p style=\"text-align: justify;\">(C) a Comiss\u00e3o Interamericana de Direitos Humanos pode emitir Opini\u00f5es Consultivas, com a finalidade de auxiliar os Estados na interpreta\u00e7\u00e3o das obriga\u00e7\u00f5es previstas no Pacto de S\u00e3o Jos\u00e9 da Costa Rica.<\/p>\n<p style=\"text-align: justify;\">(D) compete \u00e0 Corte Interamericana de Direitos Humanos receber e processar as den\u00fancias sobre as viola\u00e7\u00f5es dos direitos contidos no Pacto de S\u00e3o Jos\u00e9 da Costa Rica, que s\u00e3o encaminhadas pelos Estados e pela Comiss\u00e3o Interamericana de Direitos Humanos.<\/p>\n<h3 style=\"text-align: justify;\">Coment\u00e1rios<\/h3>\n<p style=\"text-align: justify;\">A <strong>alternativa A<\/strong> est\u00e1 incorreta, pois a Comiss\u00e3o e a Secretaria Geral s\u00e3o \u00f3rg\u00e3os de monitoramento, j\u00e1 a Corte Interamericana de Direitos Humanos constitui \u00f3rg\u00e3o judicial, respons\u00e1vel por analisar os conflitos de interesses internacionais de compet\u00eancia da OEA.<\/p>\n<p style=\"text-align: justify;\">A <strong>alternativa B<\/strong> est\u00e1 incorreta, pois nem todos os pa\u00edses assinaram o Pacto de San Jose da Costa Rica. Aqui temos que fazer uma dissocia\u00e7\u00e3o importante.<\/p>\n<p style=\"text-align: justify;\">A Carta da OEA criou a Organiza\u00e7\u00e3o dos Estados Humanos \u00e9 respons\u00e1vel por gerir o sistema interamericano.<\/p>\n<p style=\"text-align: justify;\">O Sistema Interamericano \u00e9 criado pela Conven\u00e7\u00e3o Interamericana de Direitos Humanos (o Pacto de San Jose da Costa Rica).<\/p>\n<p style=\"text-align: justify;\">Assim, somente integram o Sistema Interamericano, os pa\u00edses membros do Pacto, independentemente de serem ou n\u00e3o membros da OEA.<\/p>\n<p style=\"text-align: justify;\">A <strong>alternativa C<\/strong> est\u00e1 incorreta, pois a fun\u00e7\u00e3o consultiva \u00e9 conferida \u00e0 Corte Interamericana e n\u00e3o \u00e0 Comiss\u00e3o Interamericana.<\/p>\n<p style=\"text-align: justify;\">A <strong>alternativa D<\/strong> est\u00e1 correta e \u00e9 o gabarito da quest\u00e3o. A Corte Interamericana tem como fun\u00e7\u00f5es, a judicial \u2013 que consiste em receber e processar as den\u00fancias sobre as viola\u00e7\u00f5es de Direitos Humanos \u2013 e a consultiva \u2013 que envolve a responsabilidade de interpretar o Pacto de San Jos\u00e9 da Costa Rica.<\/p>\n<h3 style=\"text-align: justify;\">Quest\u00e3o \u2013 FADESP\/PM-PA \u2013 Pra\u00e7a &#8211; 2016<\/h3>\n<p style=\"text-align: justify;\">Em 10 de dezembro de 1948, a Declara\u00e7\u00e3o Universal dos Direitos Humanos foi finalmente adotada pela Assembleia Geral da Organiza\u00e7\u00e3o das Na\u00e7\u00f5es Unidas, marcando uma fase irrevers\u00edvel para os direitos humanos. Sobre a Declara\u00e7\u00e3o Universal dos Direitos Humanos, \u00e9 correto afirmar que<\/p>\n<p style=\"text-align: justify;\">(A) traz em seu conte\u00fado dispositivos que contemplam tanto os direitos civis e pol\u00edticos quanto os direitos econ\u00f4micos, sociais e culturais, estabelecendo que o primeiro grupo de direitos est\u00e1 acima dos demais.<\/p>\n<p style=\"text-align: justify;\">(B) possui for\u00e7a jur\u00eddica de um tratado e prev\u00ea os mecanismos para sua exigibilidade dos direitos, como peti\u00e7\u00f5es e san\u00e7\u00f5es econ\u00f4micas.<\/p>\n<p style=\"text-align: justify;\">(C) demarca ideais e princ\u00edpios que foram consubstanciados nos demais instrumentos internacionais que a seguiram, al\u00e9m de influenciar Constitui\u00e7\u00f5es e normas infraconstitucionais de diversas na\u00e7\u00f5es.<\/p>\n<p style=\"text-align: justify;\">(D) o monitoramento do cumprimento das obriga\u00e7\u00f5es contidas nos seus dispositivos \u00e9 atribui\u00e7\u00e3o da Assembleia Geral da Organiza\u00e7\u00e3o das Na\u00e7\u00f5es Unidas.<\/p>\n<h3 style=\"text-align: justify;\">Coment\u00e1rios<\/h3>\n<p style=\"text-align: justify;\">Vejamos cada uma das alternativas.<\/p>\n<p style=\"text-align: justify;\">De fato, a DUDH contempla direitos de primeira e de segunda dimens\u00e3o. Contudo, n\u00e3o podemos afirmar que o documento criou uma esp\u00e9cie de hierarquia entre um e outro, pelo que est\u00e1 errada a <strong>alternativa A<\/strong>.<\/p>\n<p style=\"text-align: justify;\">A <strong>alternativa B <\/strong>est\u00e1 incorreta. Muito embora o entendimento majorit\u00e1rio da doutrina internacional \u00e9 no sentido de que a DHDU possui for\u00e7a normativa, constitui uma declara\u00e7\u00e3o de direitos, n\u00e3o prevendo em seu texto instrumentos de exigibilidade. Isso somente existir no Sistema Global com a edi\u00e7\u00e3o dos Pactos Internacionais.<\/p>\n<p style=\"text-align: justify;\">A <strong>alternativa C<\/strong> est\u00e1 correta e \u00e9 o gabarito da quest\u00e3o, pois \u00e9 justamente essa a finalidade da DUDH no Sistema Global de Direitos Humanos.<\/p>\n<p style=\"text-align: justify;\">A<strong> alternativa D<\/strong>, por sua vez, est\u00e1 incorreta, pois o monitoramento do cumprimento dos tratados e conven\u00e7\u00f5es internacionais no \u00e2mbito do Sistema Global de Direitos Humanos fica a cargo dos Comit\u00eas e Comiss\u00f5es, e n\u00e3o da Assembleia Geral da ONU.<\/p>\n<p style=\"text-align: justify;\">&#8212;<\/p>\n<p style=\"text-align: justify;\">\u00c9 isso, n\u00e3o vislumbramos possibilidade de recurso das quest\u00f5es acima.<\/p>\n<p style=\"text-align: justify;\">Caso voc\u00ea esteja estudando para concursos que cobrem a disciplina de Direitos Humanos, conhe\u00e7a os cursos dispon\u00edveis no Estrat\u00e9gia Concursos.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.estrategiaconcursos.com.br\/cursosPorMateria\/direitos-humanos-64\/\"><strong>https:\/\/www.estrategiaconcursos.com.br\/cursosPorMateria\/direitos-humanos-64<\/strong><\/a><\/p>\n<p style=\"text-align: justify;\">Nos acompanhe nas redes sociais! Com frequ\u00eancia disponibilizamos informa\u00e7\u00f5es relativas a concursos, provas comentadas, sugest\u00f5es de recurso etc. Acompanhe-nos nos canais abaixo:<\/p>\n<p style=\"text-align: justify;\">FACEBOOK<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.facebook.com\/direitoshumanosparaconcursos\"><strong>https:\/\/www.facebook.com\/direitoshumanosparaconcursos<\/strong><\/a><\/p>\n<p style=\"text-align: justify;\">PERISCOPE<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.periscope.tv\/rstorques\"><strong>@rstorques<\/strong><\/a><\/p>\n<p style=\"text-align: justify;\">YOUTUBE<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.youtube.com\/c\/RicardoStrapassonTorques\"><strong>https:\/\/www.youtube.com\/c\/RicardoStrapassonTorques<\/strong><\/a><\/p>\n<p style=\"text-align: justify;\">E-MAIL<\/p>\n<p style=\"text-align: justify;\"><a href=\"mailto:rst.estrategia@gmail.com\"><strong>rst.estrategia@gmail.com<\/strong><\/a><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A banca FADESP divulgou \u00a0a prova e o gabarito preliminares do concurso para os cargos de oficial e pra\u00e7a da Pol\u00edcia Militar do Estado do Par\u00e1. Neste artigo vamos analisar as quest\u00f5es de Direitos Humanos. Tivemos 5 quest\u00f5es para o cargo de oficial e outras 2 quest\u00f5es para o cargo de soldado. Tal como era [&hellip;]<\/p>\n","protected":false},"author":180,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"post_tipo":"article","footnotes":""},"categories":[],"tags":[525,1348],"tax_estado":[],"class_list":["post-45030","post","type-post","status-publish","format-standard","hentry","tag-direitos-humanos","tag-pm-pa"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.2 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Coment\u00e1rios \u00e0 prova de Direitos Humanos PM-PA<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/comentarios-prova-de-direitos-humanos-pm-pa\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Coment\u00e1rios \u00e0 prova de Direitos Humanos PM-PA\" \/>\n<meta property=\"og:description\" content=\"A banca FADESP divulgou \u00a0a prova e o gabarito preliminares do concurso para os cargos de oficial e pra\u00e7a da Pol\u00edcia Militar do Estado do Par\u00e1. Neste artigo vamos analisar as quest\u00f5es de Direitos Humanos. Tivemos 5 quest\u00f5es para o cargo de oficial e outras 2 quest\u00f5es para o cargo de soldado. Tal como era [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/comentarios-prova-de-direitos-humanos-pm-pa\/\" \/>\n<meta property=\"og:site_name\" content=\"Estrat\u00e9gia Concursos\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/ricardo.s.torques\" \/>\n<meta property=\"article:published_time\" content=\"2016-08-02T16:30:02+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-08-02T16:49:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2016\/08\/02132903\/PMPA.jpg\" \/>\n<meta name=\"author\" content=\"Ricardo Torques\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:site\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ricardo Torques\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"15 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/comentarios-prova-de-direitos-humanos-pm-pa\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/comentarios-prova-de-direitos-humanos-pm-pa\/\"},\"author\":{\"name\":\"Ricardo Torques\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/aa39cf5ddb518e5bdce27c35788405e2\"},\"headline\":\"Coment\u00e1rios \u00e0 prova de Direitos Humanos PM-PA\",\"datePublished\":\"2016-08-02T16:30:02+00:00\",\"dateModified\":\"2016-08-02T16:49:07+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/comentarios-prova-de-direitos-humanos-pm-pa\/\"},\"wordCount\":3099,\"commentCount\":2,\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/comentarios-prova-de-direitos-humanos-pm-pa\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2016\/08\/02132903\/PMPA.jpg\",\"keywords\":[\"Direitos Humanos\",\"PM PA\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/comentarios-prova-de-direitos-humanos-pm-pa\/#respond\"]}],\"copyrightYear\":\"2016\",\"copyrightHolder\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/comentarios-prova-de-direitos-humanos-pm-pa\/\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/comentarios-prova-de-direitos-humanos-pm-pa\/\",\"name\":\"Coment\u00e1rios \u00e0 prova de Direitos Humanos PM-PA\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/comentarios-prova-de-direitos-humanos-pm-pa\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/comentarios-prova-de-direitos-humanos-pm-pa\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2016\/08\/02132903\/PMPA.jpg\",\"datePublished\":\"2016-08-02T16:30:02+00:00\",\"dateModified\":\"2016-08-02T16:49:07+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/comentarios-prova-de-direitos-humanos-pm-pa\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/comentarios-prova-de-direitos-humanos-pm-pa\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/comentarios-prova-de-direitos-humanos-pm-pa\/#primaryimage\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2016\/08\/02132903\/PMPA.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2016\/08\/02132903\/PMPA.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/comentarios-prova-de-direitos-humanos-pm-pa\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Coment\u00e1rios \u00e0 prova de Direitos Humanos PM-PA\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"name\":\"Estrat\u00e9gia Concursos\",\"description\":\"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.\",\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\",\"name\":\"Estrat\u00e9gia Concursos\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"width\":230,\"height\":60,\"caption\":\"Estrat\u00e9gia Concursos\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/EstratConcursos\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/aa39cf5ddb518e5bdce27c35788405e2\",\"name\":\"Ricardo Torques\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/ce9ac6c3cff25fe86d15ed568ebc64d1724baf5c0693133bcb1f6073f712f92a?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/ce9ac6c3cff25fe86d15ed568ebc64d1724baf5c0693133bcb1f6073f712f92a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/ce9ac6c3cff25fe86d15ed568ebc64d1724baf5c0693133bcb1f6073f712f92a?s=96&d=mm&r=g\",\"caption\":\"Ricardo Torques\"},\"sameAs\":[\"https:\/\/www.facebook.com\/ricardo.s.torques\"],\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/ricardotorquesestrategiaconcursos-com-br\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Coment\u00e1rios \u00e0 prova de Direitos Humanos PM-PA","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.estrategiaconcursos.com.br\/blog\/comentarios-prova-de-direitos-humanos-pm-pa\/","og_locale":"pt_BR","og_type":"article","og_title":"Coment\u00e1rios \u00e0 prova de Direitos Humanos PM-PA","og_description":"A banca FADESP divulgou \u00a0a prova e o gabarito preliminares do concurso para os cargos de oficial e pra\u00e7a da Pol\u00edcia Militar do Estado do Par\u00e1. Neste artigo vamos analisar as quest\u00f5es de Direitos Humanos. Tivemos 5 quest\u00f5es para o cargo de oficial e outras 2 quest\u00f5es para o cargo de soldado. Tal como era [&hellip;]","og_url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/comentarios-prova-de-direitos-humanos-pm-pa\/","og_site_name":"Estrat\u00e9gia Concursos","article_author":"https:\/\/www.facebook.com\/ricardo.s.torques","article_published_time":"2016-08-02T16:30:02+00:00","article_modified_time":"2016-08-02T16:49:07+00:00","og_image":[{"url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2016\/08\/02132903\/PMPA.jpg","type":"","width":"","height":""}],"author":"Ricardo Torques","twitter_card":"summary_large_image","twitter_creator":"@EstratConcursos","twitter_site":"@EstratConcursos","twitter_misc":{"Escrito por":"Ricardo Torques","Est. tempo de leitura":"15 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/comentarios-prova-de-direitos-humanos-pm-pa\/#article","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/comentarios-prova-de-direitos-humanos-pm-pa\/"},"author":{"name":"Ricardo Torques","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/aa39cf5ddb518e5bdce27c35788405e2"},"headline":"Coment\u00e1rios \u00e0 prova de Direitos Humanos PM-PA","datePublished":"2016-08-02T16:30:02+00:00","dateModified":"2016-08-02T16:49:07+00:00","mainEntityOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/comentarios-prova-de-direitos-humanos-pm-pa\/"},"wordCount":3099,"commentCount":2,"publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/comentarios-prova-de-direitos-humanos-pm-pa\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2016\/08\/02132903\/PMPA.jpg","keywords":["Direitos Humanos","PM PA"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/comentarios-prova-de-direitos-humanos-pm-pa\/#respond"]}],"copyrightYear":"2016","copyrightHolder":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/comentarios-prova-de-direitos-humanos-pm-pa\/","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/comentarios-prova-de-direitos-humanos-pm-pa\/","name":"Coment\u00e1rios \u00e0 prova de Direitos Humanos PM-PA","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/comentarios-prova-de-direitos-humanos-pm-pa\/#primaryimage"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/comentarios-prova-de-direitos-humanos-pm-pa\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2016\/08\/02132903\/PMPA.jpg","datePublished":"2016-08-02T16:30:02+00:00","dateModified":"2016-08-02T16:49:07+00:00","breadcrumb":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/comentarios-prova-de-direitos-humanos-pm-pa\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/comentarios-prova-de-direitos-humanos-pm-pa\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/comentarios-prova-de-direitos-humanos-pm-pa\/#primaryimage","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2016\/08\/02132903\/PMPA.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2016\/08\/02132903\/PMPA.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/comentarios-prova-de-direitos-humanos-pm-pa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.estrategiaconcursos.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Coment\u00e1rios \u00e0 prova de Direitos Humanos PM-PA"}]},{"@type":"WebSite","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","name":"Estrat\u00e9gia Concursos","description":"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.","publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization","name":"Estrat\u00e9gia Concursos","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","width":230,"height":60,"caption":"Estrat\u00e9gia Concursos"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/EstratConcursos"]},{"@type":"Person","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/aa39cf5ddb518e5bdce27c35788405e2","name":"Ricardo Torques","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/ce9ac6c3cff25fe86d15ed568ebc64d1724baf5c0693133bcb1f6073f712f92a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ce9ac6c3cff25fe86d15ed568ebc64d1724baf5c0693133bcb1f6073f712f92a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ce9ac6c3cff25fe86d15ed568ebc64d1724baf5c0693133bcb1f6073f712f92a?s=96&d=mm&r=g","caption":"Ricardo Torques"},"sameAs":["https:\/\/www.facebook.com\/ricardo.s.torques"],"url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/ricardotorquesestrategiaconcursos-com-br\/"}]}},"_links":{"self":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/45030","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/users\/180"}],"replies":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/comments?post=45030"}],"version-history":[{"count":5,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/45030\/revisions"}],"predecessor-version":[{"id":45036,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/45030\/revisions\/45036"}],"wp:attachment":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media?parent=45030"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/categories?post=45030"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tags?post=45030"},{"taxonomy":"tax_estado","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tax_estado?post=45030"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}