{"id":436025,"date":"2019-10-17T21:24:01","date_gmt":"2019-10-18T00:24:01","guid":{"rendered":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?p=436025"},"modified":"2021-01-14T16:48:22","modified_gmt":"2021-01-14T19:48:22","slug":"redacao-enem-2019","status":"publish","type":"post","link":"https:\/\/www.estrategiaconcursos.com.br\/blog\/redacao-enem-2019\/","title":{"rendered":"Reda\u00e7\u00e3o ENEM 2019 &#8211; Cartilha do Participante &#8211; O que mudou?"},"content":{"rendered":"\n<p><strong>Ol\u00e1, caros estudantes do ENEM!<\/strong><\/p>\n\n\n\n<p>No \u00faltimo dia 10, o INEP lan\u00e7ou a cartilha de <a href=\"https:\/\/blog.estrategiavestibulares.com.br\/enem\/preparacao-enem\/\" target=\"_blank\" rel=\"noreferrer noopener\">reda\u00e7\u00e3o ENEM<\/a> (cartilha do participante 2019). N\u00f3s, do Estrat\u00e9gia ENEM, fizemos a leitura na \u00edntegra para compara\u00e7\u00e3o com a cartilha do ano passado (2018) e constatamos que n\u00e3o houve nenhuma altera\u00e7\u00e3o!<br \/>Isso \u00e9 \u00f3timo, pois quer dizer que toda a prepara\u00e7\u00e3o oferecida aos nossos alunos at\u00e9 aqui est\u00e1 inteira, robusta e eficaz! As nossas aulas est\u00e3o totalmente dentro do que postula o INEP sobre como os candidatos devem elaborar a reda\u00e7\u00e3o no dia da prova.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-como-ser-a-prova-de-reda-o-no-enem-2019-reda-o-enem\"><strong><span style=\"color: #ff0000;\">Como ser\u00e1 a prova de reda\u00e7\u00e3o no ENEM 2019 (Reda\u00e7\u00e3o ENEM )?<\/span><\/strong><\/h2>\n\n\n\n<p>Conforme o esperado e como de costume, segundo a cartilha de reda\u00e7\u00e3o 2019 (cartilha do participante 2019), <span style=\"color: #0000ff;\"><strong>os candidatos ter\u00e3o que elaborar um texto dissertativo-argumentativo<\/strong><\/span>, em prosa, sobre um tema de ordem social, cient\u00edfica, cultural ou pol\u00edtica.<br \/>Os aspectos a serem avaliados continuam relacionados \u00e0s compet\u00eancias que devem ter sido desenvolvidas durante os anos de escolaridade. Na reda\u00e7\u00e3o, o aluno dever\u00e1 <strong><span style=\"color: #0000ff;\">defender uma tese<\/span><\/strong> que a cartilha conceitua como uma opini\u00e3o a respeito do tema proposto, apoiada sempre em <strong><span style=\"color: #0000ff;\">argumentos consistentes<\/span><\/strong>, estruturados com coer\u00eancia e coes\u00e3o, formando uma unidade textual.<br \/>O texto dever\u00e1 ser redigido de acordo com a modalidade escrita formal da l\u00edngua portuguesa. Al\u00e9m disso, o candidato dever\u00e1 elaborar uma <strong><span style=\"color: #0000ff;\">proposta de interven\u00e7\u00e3o social<\/span><\/strong> para o problema apresentado no desenvolvimento do texto que respeite os direitos humanos.<br \/>A cartilha orienta os candidatos a utilizarem a seguinte estrutura para elaborar o texto:<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter\"><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/redacao-enem-2019-cartilha-do-participante-o-que-mudou\/estrutura-cartilha-enem\/\" rel=\"attachment wp-att-436033\"><img loading=\"lazy\" decoding=\"async\" width=\"291\" height=\"479\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2019\/10\/17120113\/Estrutura-cartilha-ENEM.png\" alt=\"Estrutura INEP reda\u00e7\u00e3o ENEM 2019\" class=\"wp-image-436033\" srcset=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2019\/10\/17120113\/Estrutura-cartilha-ENEM.png 291w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2019\/10\/17120113\/Estrutura-cartilha-ENEM.png 182w\" sizes=\"auto, (max-width: 291px) 100vw, 291px\" \/><\/a><\/figure><\/div>\n\n\n\n<p>Diante dessa imagem retirada da pr\u00f3pria cartilha, a nossa orienta\u00e7\u00e3o \u00e9 que os candidatos a usem como forma de iniciar o roteiro da reda\u00e7\u00e3o. <strong><span style=\"color: #0000ff;\">Inicie seu texto com o tema, insira, na sequ\u00eancia, a tese<\/span><\/strong>. A partir da\u00ed, e em novo par\u00e1grafo, coloque os argumentos e finalize com um par\u00e1grafo de interven\u00e7\u00e3o. A sua reda\u00e7\u00e3o ter\u00e1, ent\u00e3o, de 4 a 5 par\u00e1grafos seguindo o que se espera de um texto dissertativo-argumentativo para na reda\u00e7\u00e3o ENEM.<\/p>\n\n\n\n<p>Para esclarecer melhor, observe e grave a seguinte estrutura! Veja como ir\u00e1 facilitar a elabora\u00e7\u00e3o do seu texto:<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter\"><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/redacao-enem-2019-cartilha-do-participante-o-que-mudou\/estrutura-em-paragrafos-redacao-enem\/\" rel=\"attachment wp-att-436038\"><img decoding=\"async\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2019\/10\/17120615\/Estrutura-em-par%C3%A1grafos-reda%C3%A7%C3%A3o-ENEM.png.png\" alt=\"Quantos par\u00e1grafos deve ter a reda\u00e7\u00e3o do ENEM \" class=\"wp-image-436038\"\/><\/a><\/figure><\/div>\n\n\n\n<p>Simples, n\u00e3o \u00e9? Siga esse padr\u00e3o caso tenha dificuldade em elaborar um texto dissertativo-argumentativo e, certamente, ter\u00e1 sucesso!<\/p>\n\n\n\n<p>\u00c9 bem prov\u00e1vel que voc\u00ea esteja cheio de d\u00favidas! A seguir, vou responder \u00e0s d\u00favidas mais frequentes que est\u00e3o, inclusive, feitas na cartilha de reda\u00e7\u00e3o do ENEM 2019!<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-como-meu-texto-ser-avaliado-reda-o-enem\"><span style=\"color: #ff0000;\">Como meu texto ser\u00e1 avaliado (Reda\u00e7\u00e3o ENEM )?<\/span><\/h2>\n\n\n\n<p>A reda\u00e7\u00e3o do ENEM vale 1.000 pontos e ser\u00e1 avaliada por, pelo menos, dois professores, de forma independente, sem que um conhe\u00e7a a nota atribu\u00edda pelo outro. Cada avaliador atribuir\u00e1 uma nota entre 0 e 200 pontos para cada uma das cinco compet\u00eancias. A soma desses pontos compor\u00e1 a nota total de cada avaliador, que pode chegar a 1.000 pontos. A nota final do participante ser\u00e1 a m\u00e9dia aritm\u00e9tica das notas totais atribu\u00eddas pelos dois avaliadores.<\/p>\n\n\n\n<p><strong><em><span style=\"color: #3366ff;\">Aten\u00e7\u00e3o: Considera-se discrep\u00e2ncia quando as notas atribu\u00eddas pelos avaliadores:<\/span><\/em><\/strong><br \/><strong><em><span style=\"color: #3366ff;\">\u2022 diferirem, no total, por mais de 100 pontos; ou<\/span><\/em><\/strong><br \/><strong><em><span style=\"color: #3366ff;\">\u2022 obtiverem diferen\u00e7a superior a 80 pontos em qualquer uma das compet\u00eancias.<\/span><\/em><\/strong><\/p>\n\n\n\n<p>Caso haja discrep\u00e2ncia entre as duas notas da avalia\u00e7\u00e3o, a reda\u00e7\u00e3o ser\u00e1 avaliada, de forma independente, por um terceiro avaliador. A nota final ser\u00e1 a m\u00e9dia aritm\u00e9tica das duas notas totais que mais se aproximarem. Se a discrep\u00e2ncia ainda continuar depois da terceira avalia\u00e7\u00e3o, a reda\u00e7\u00e3o ser\u00e1 avaliada por uma banca presencial composta por tr\u00eas professores, que atribuir\u00e1 a nota final do participante.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-quais-s-o-os-crit-rios-da-reda-o-enem\"><span style=\"color: #ff0000;\">Quais s\u00e3o os crit\u00e9rios da Reda\u00e7\u00e3o ENEM ?<\/span><\/h2>\n\n\n\n<p>Os dois professores que avaliar\u00e3o seu desempenho seguir\u00e3o os crit\u00e9rios da tabela a seguir (publicada na cartilha do participante ENEM 2019):<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter\"><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/redacao-enem-2019-cartilha-do-participante-o-que-mudou\/competencias-redacao-enem\/\" rel=\"attachment wp-att-436044\"><img decoding=\"async\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2019\/10\/17121418\/Compet%C3%AAncias-reda%C3%A7%C3%A3o-enem.png\" alt=\"Quais s\u00e3o as compet\u00eancias da reda\u00e7\u00e3o enem \" class=\"wp-image-436044\"\/><\/a><\/figure><\/div>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-quais-as-raz-es-para-se-atribuir-nota-0-zero-a-uma-reda-o-enem\"><span style=\"color: #ff0000;\">Quais as raz\u00f5es para se atribuir nota 0 (zero) a uma reda\u00e7\u00e3o ENEM?<\/span><\/h2>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>A reda\u00e7\u00e3o receber\u00e1 nota 0 (zero) se apresentar uma das caracter\u00edsticas a seguir:<br \/>\u2022 fuga total ao tema;<br \/>\u2022 n\u00e3o obedi\u00eancia \u00e0 estrutura dissertativo-argumentativa;<br \/>\u2022 extens\u00e3o total de at\u00e9 7 linhas;<br \/>\u2022 c\u00f3pia integral de texto(s) da Prova de Reda\u00e7\u00e3o e\/ou do Caderno de Quest\u00f5es;<br \/>\u2022 improp\u00e9rios, desenhos e outras formas propositais de anula\u00e7\u00e3o, em qualquer parte da folha de reda\u00e7\u00e3o;<br \/>\u2022 n\u00fameros ou sinais gr\u00e1ficos fora do texto e sem fun\u00e7\u00e3o clara;<br \/>\u2022 parte deliberadamente desconectada do tema proposto;<br \/>\u2022 assinatura, nome, apelido, codinome ou rubrica fora do local devidamente designada para a assinatura do participante;<br \/>\u2022 texto predominante ou integralmente em l\u00edngua estrangeira; e<br \/>\u2022 folha de reda\u00e7\u00e3o em branco, mesmo que haja texto escrito na folha de rascunho.<\/p><\/blockquote>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-como-ser-avaliada-a-reda-o-enem-de-participantes-surdos-ou-com-defici-ncia-auditiva-e-de-participantes-com-dislexia\"><span style=\"color: #ff0000;\">Como ser\u00e1 avaliada a reda\u00e7\u00e3o ENEM de participantes surdos ou com defici\u00eancia auditiva? E de participantes com dislexia?<\/span><\/h2>\n\n\n\n<p>Ser\u00e3o adotados mecanismos de avalia\u00e7\u00e3o coerentes com o aprendizado da l\u00edngua portuguesa como segunda l\u00edngua, de acordo com o Decreto n\u00ba 5.626, de 22 de dezembro de 2005, e\/ou que levem em conta quest\u00f5es lingu\u00edsticas espec\u00edficas relacionadas \u00e0 dislexia.<\/p>\n\n\n\n<p>A cartilha do participante do ENEM 2019 deixa alguns avisos importantes para os candidatos:<\/p>\n\n\n\n<p><span style=\"color: #0000ff;\">IMPORTANTE!<\/span><br \/><span style=\"color: #0000ff;\">Para efeito de avalia\u00e7\u00e3o e de contagem do m\u00ednimo de linhas escritas, os trechos que representarem c\u00f3pia dos textos da Prova de Reda\u00e7\u00e3o ou do Caderno de Quest\u00f5es ser\u00e3o desconsiderados em rela\u00e7\u00e3o ao total de linhas escritas, valendo somente as que foram produzidas pelo participante.<\/span><\/p>\n\n\n\n<p><span style=\"color: #0000ff;\">IMPORTANTE!<\/span><br \/><span style=\"color: #0000ff;\">Procure escrever sua reda\u00e7\u00e3o com letra leg\u00edvel, para evitar d\u00favidas no momento da avalia\u00e7\u00e3o. Reda\u00e7\u00e3o com letra ileg\u00edvel poder\u00e1 n\u00e3o ser avaliada.<\/span><\/p>\n\n\n\n<p><span style=\"color: #0000ff;\">IMPORTANTE!<\/span><br \/><span style=\"color: #0000ff;\">O t\u00edtulo \u00e9 um elemento opcional na produ\u00e7\u00e3o da sua reda\u00e7\u00e3o, assim, embora seja considerado como linha escrita, n\u00e3o \u00e9 avaliado em nenhum aspecto relacionado \u00e0s compet\u00eancias da matriz de refer\u00eancia.<\/span><\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-o-que-avalia-cada-uma-das-5-compet-ncias-na-reda-o-enem\"><span style=\"color: #ff0000;\">O que avalia cada uma das 5 compet\u00eancias na Reda\u00e7\u00e3o ENEM ?<\/span><\/h2>\n\n\n\n<p><strong>COMPET\u00caNCIA 1<\/strong><br \/><strong>DEMONSTRAR DOM\u00cdNIO DA MODALIDADE ESCRITA FORMAL DA L\u00cdNGUA PORTUGUESA<\/strong><\/p>\n\n\n\n<p>\u00c9 a compet\u00eancia que avalia na reda\u00e7\u00e3o ENEM se o candidato domina a modalidade escrita formal da l\u00edngua portuguesa, o que inclui o conhecimento das conven\u00e7\u00f5es da escrita, dentre as quais se encontram as regras de ortografia e de acentua\u00e7\u00e3o gr\u00e1fica regidas pelo atual Acordo Ortogr\u00e1fico. Os examinadores avaliam tamb\u00e9m a fluidez do texto no uso adequado das regras gramaticais.<br \/>Para que os candidatos tenham mais clareza a respeito das expectativas que se t\u00eam de um concluinte do ensino m\u00e9dio em termos de dom\u00ednio da modalidade escrita formal, a cartilha do participante 2019 trouxe os principais aspectos que guiam o olhar do avaliador no momento de definir o n\u00edvel em que seu texto se encontra na Compet\u00eancia 1.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>Em primeiro lugar, voc\u00ea deve se atentar ao fato de que a escrita formal \u00e9 a modalidade da l\u00edngua associada a textos dissertativo-argumentativos. Assim, voc\u00ea ser\u00e1 alertado sobre a obrigatoriedade de usar a modalidade formal j\u00e1 na proposta de reda\u00e7\u00e3o: \u201cA partir da leitura dos textos motivadores e com base nos conhecimentos constru\u00eddos ao longo de sua forma\u00e7\u00e3o, redija texto dissertativo-argumentativo em modalidade escrita formal da l\u00edngua portuguesa sobre o tema&#8230;\u201d.<br \/>Desse modo, o avaliador corrigir\u00e1 sua reda\u00e7\u00e3o, nessa Compet\u00eancia, considerando os poss\u00edveis problemas de constru\u00e7\u00e3o sint\u00e1tica e a presen\u00e7a de desvios (de conven\u00e7\u00f5es da escrita, gramaticais, de escolha de registro e de escolha vocabular).<br \/>Em rela\u00e7\u00e3o \u00e0 constru\u00e7\u00e3o sint\u00e1tica, voc\u00ea deve estruturar as ora\u00e7\u00f5es e os per\u00edodos de seu texto sempre buscando garantir que eles estejam completos e contribuam para a fluidez da leitura.<br \/>Quanto aos desvios, voc\u00ea deve estar atento aos seguintes aspectos:<br \/>\u2022 Conven\u00e7\u00f5es da escrita: acentua\u00e7\u00e3o, ortografa, uso de h\u00edfen, emprego de letras mai\u00fasculas e min\u00fasculas e separa\u00e7\u00e3o sil\u00e1bica (translinea\u00e7\u00e3o).<br \/>\u2022 Gramaticais: reg\u00eancia verbal e nominal, concord\u00e2ncia verbal e nominal, pontua\u00e7\u00e3o, paralelismo, emprego de pronomes e crase.<br \/>\u2022 Escolha de registro: adequa\u00e7\u00e3o \u00e0 modalidade escrita formal, isto \u00e9, aus\u00eancia de uso de registro informal e\/ou de marcas de oralidade.<br \/>\u2022 Escolha vocabular: emprego de vocabul\u00e1rio preciso, o que significa que as palavras selecionadas s\u00e3o usadas em seu sentido correto e s\u00e3o apropriadas ao contexto em que aparecem.<\/p><\/blockquote>\n\n\n\n<p>O quadro a seguir apresenta os seis n\u00edveis de desempenho que ser\u00e3o utilizados para avaliar a Compet\u00eancia 1 nas reda\u00e7\u00f5es do Enem 2019:<\/p>\n\n\n\n<p>COMPET\u00caNCIA 1:<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter\"><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/redacao-enem-2019-cartilha-do-participante-o-que-mudou\/competencia-1\/\" rel=\"attachment wp-att-436047\"><img decoding=\"async\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2019\/10\/17121840\/Compet%C3%AAncia-1.png.png\" alt=\"Compet\u00eancia 1\" class=\"wp-image-436047\"\/><\/a><\/figure><\/div>\n\n\n\n<p><strong>COMPET\u00caNCIA 2<\/strong><br \/><strong>COMPREENDER A PROPOSTA DE REDA\u00c7\u00c3O E APLICAR CONCEITOS DAS V\u00c1RIAS \u00c1REAS DE CONHECIMENTO PARA DESENVOLVER O TEMA, DENTRO DOS LIMITES ESTRUTURAIS DO TEXTO DISSERTATIVO-ARGUMENTATIVO EM PROSA<\/strong><\/p>\n\n\n\n<p>Os examinadores visam avaliar na compet\u00eancia 2 se o candidato <span style=\"color: #3366ff;\"><strong>compreendeu a proposta de reda\u00e7\u00e3o<\/strong><\/span>. Al\u00e9m disso, se ele conseguiu desenvolver a proposta na forma de um texto dissertativo-argumentativo \u2013 ou seja, a proposta exige que o participante escreva um texto que demonstra, por meio de argumenta\u00e7\u00e3o, a assertividade de uma ideia ou de uma tese. A cartilha do participante chama a aten\u00e7\u00e3o para o fato de que se espera n\u00e3o s\u00f3 a exposi\u00e7\u00e3o do tema, mas um posicionamento cr\u00edtico por parte do candidato. Al\u00e9m disso, \u00e9 preciso que a tese defendida no texto esteja relacionada ao tema definido na proposta. \u00c9 dessa forma que se atende \u00e0s exig\u00eancias expressas pela Compet\u00eancia 2 da matriz de avalia\u00e7\u00e3o do Enem.<br \/>Lembre-se: o tema apresentado \u00e9 normalmente amplo, mas constitui o n\u00facleo das ideias em torno das quais a tese se organiza, ou seja, \u00e9 caracterizado por ser uma delimita\u00e7\u00e3o de um assunto mais abrangente. Por isso, \u00e9 preciso atender ao recorte tem\u00e1tico definido para evitar tangenci\u00e1-lo ou, ainda pior, desenvolver um tema distinto do determinado pela proposta.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>Seguem algumas recomenda\u00e7\u00f5es (retiradas da cartilha do participante 2019) para atender plenamente \u00e0s expectativas em rela\u00e7\u00e3o \u00e0 Compet\u00eancia 2:<br \/>\u2022 Leia com aten\u00e7\u00e3o a proposta da reda\u00e7\u00e3o e os textos motivadores, para compreender bem o que est\u00e1 sendo solicitado.<br \/>\u2022 Evite ficar preso \u00e0s ideias desenvolvidas nos textos motivadores, porque elas foram apresentadas apenas para despertar uma re\ufb02ex\u00e3o sobre o tema.<br \/>\u2022 N\u00e3o copie trechos dos textos motivadores. A recorr\u00eancia de c\u00f3pia \u00e9 avaliada negativamente e far\u00e1 com que sua reda\u00e7\u00e3o tenha uma pontua\u00e7\u00e3o mais baixa.<br \/>\u2022 Re\ufb02ita sobre o tema proposto para definir qual ser\u00e1 o foco da sua discuss\u00e3o, isto \u00e9, para decidir como abord\u00e1-lo, qual ser\u00e1 o ponto de vista adotado e como defend\u00ea-lo.<br \/>\u2022 Utilize informa\u00e7\u00f5es de v\u00e1rias \u00e1reas do conhecimento, demonstrando que voc\u00ea est\u00e1 atualizado em rela\u00e7\u00e3o ao que acontece no mundo. Essas informa\u00e7\u00f5es devem ser pertinentes ao tema e usadas de modo produtivo no seu texto, evidenciando que elas servem a um prop\u00f3sito muito bem definido: ajud\u00e1-lo a validar seu ponto de vista. Isso significa que essas informa\u00e7\u00f5es devem estar articuladas \u00e0 discuss\u00e3o desenvolvida em sua reda\u00e7\u00e3o. Informa\u00e7\u00f5es soltas no texto, por mais variadas e interessantes que sejam, perdem sua relev\u00e2ncia quando n\u00e3o associadas \u00e0 defesa do ponto de vista desenvolvido em seu texto.<br \/>\u2022 Mantenha-se dentro dos limites do tema proposto, tomando cuidado para n\u00e3o se afastar do seu foco. Esse \u00e9 um dos principais problemas identificados nas reda\u00e7\u00f5es. Nesse caso, duas situa\u00e7\u00f5es podem ocorrer: fuga total ou tangenciamento ao tema.<\/p><\/blockquote>\n\n\n\n<p>Vejam um exemplo interessante que o INEP apresentou sobre tangenciamento do tema e compreens\u00e3o da proposta tomando como base o tema da reda\u00e7\u00e3o de 2018.<\/p>\n\n\n\n<p><span style=\"color: #3366ff;\"><strong>O QUE \u00c9 TANGENCIAR O TEMA?<\/strong><\/span><\/p>\n\n\n\n<p>Considera-se tangenciamento ao tema uma abordagem parcial baseada somente no assunto mais amplo a que o tema est\u00e1 vinculado, deixando em segundo plano a discuss\u00e3o em torno do eixo tem\u00e1tico objetivamente proposto.<\/p>\n\n\n\n<p>No Enem 2018, o tema se referia \u00e0 discuss\u00e3o sobre a Manipula\u00e7\u00e3o do comportamento do usu\u00e1rio pelo controle de dados na internet, Sobre esse tema, foi configurado como tangenciamento ao tema o encaminhamento que tratou apenas de assunto a ele relacionado, por exemplo, internet ou elemento do universo da internet (rede, browser, navegador, plataforma virtual, sites, e-mail, WhatsApp, Net\ufb02ix, Spotify, hackers, haters, trolls, fake news etc.); a manipula\u00e7\u00e3o do comportamento do usu\u00e1rio na e\/ou pela internet, sem men\u00e7\u00e3o ao controle de dados; controle de dados na internet, sem men\u00e7\u00e3o \u00e0 manipula\u00e7\u00e3o do comportamento do usu\u00e1rio.<\/p>\n\n\n\n<p>Agora analise um trecho (primeiro par\u00e1grafo) de uma reda\u00e7\u00e3o que recebeu nota m\u00e1xima e que est\u00e1 na cartilha do participante 2019 como exemplo:<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter\"><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/redacao-enem-2019-cartilha-do-participante-o-que-mudou\/exemplo-1\/\" rel=\"attachment wp-att-436055\"><img loading=\"lazy\" decoding=\"async\" width=\"921\" height=\"320\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2019\/10\/17122944\/Exemplo-1.png\" alt=\"exemplo 1\" class=\"wp-image-436055\" srcset=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2019\/10\/17122944\/Exemplo-1.png 921w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2019\/10\/17122944\/Exemplo-1.png 300w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2019\/10\/17122944\/Exemplo-1.png 768w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2019\/10\/17122944\/Exemplo-1.png 610w\" sizes=\"auto, (max-width: 921px) 100vw, 921px\" \/><\/a><\/figure><\/div>\n\n\n\n<p>A aluna acertou ao abordar o tema de maneira mais geral e, na sequ\u00eancia, apresentar a tese usando as palavras chaves \u201cmanipula\u00e7\u00e3o do comportamento&#8230; dados&#8230;\u201d.<\/p>\n\n\n\n<p>O quadro a seguir apresenta os seis n\u00edveis de desempenho que ser\u00e3o utilizados para avaliar a Compet\u00eancia 2 nas reda\u00e7\u00f5es do Enem 2019:<\/p>\n\n\n\n<p><strong>COMPET\u00caNCIA 2:<\/strong><\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter\"><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/redacao-enem-2019-cartilha-do-participante-o-que-mudou\/competencia-2\/\" rel=\"attachment wp-att-436057\"><img loading=\"lazy\" decoding=\"async\" width=\"622\" height=\"336\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2019\/10\/17125310\/cOMPETENCIA-2.png.png\" alt=\"Compet\u00eancia 2\" class=\"wp-image-436057\" srcset=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2019\/10\/17125310\/cOMPETENCIA-2.png.png 622w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2019\/10\/17125310\/cOMPETENCIA-2.png.png 300w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2019\/10\/17125310\/cOMPETENCIA-2.png.png 610w\" sizes=\"auto, (max-width: 622px) 100vw, 622px\" \/><\/a><\/figure><\/div>\n\n\n\n<p><strong>COMPET\u00caNCIA 3<\/strong><br \/><strong>SELECIONAR, RELACIONAR, ORGANIZAR E INTERPRETAR INFORMA\u00c7\u00d5ES, FATOS, OPINI\u00d5ES E ARGUMENTOS EM DEFESA DE UM PONTO DE VISTA<\/strong><\/p>\n\n\n\n<p>A compet\u00eancia 3 avalia a forma como o candidato seleciona, relaciona, organiza e interpreta informa\u00e7\u00f5es, fatos, opini\u00f5es e argumentos em defesa do ponto de vista escolhido como tese. \u00c9 preciso, ent\u00e3o, elaborar um texto que apresente, claramente, uma ideia a ser defendida e os argumentos que justifiquem a posi\u00e7\u00e3o assumida por voc\u00ea em rela\u00e7\u00e3o \u00e0 tem\u00e1tica da proposta de reda\u00e7\u00e3o.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>A Compet\u00eancia 3 trata da inteligibilidade do seu texto, ou seja, de sua coer\u00eancia e da plausibilidade entre as ideias apresentadas, o que \u00e9 garantido pelo planejamento pr\u00e9vio \u00e0 escrita, ou seja, pela elabora\u00e7\u00e3o de um projeto de texto.<br \/>A inteligibilidade da sua reda\u00e7\u00e3o depende, portanto, dos seguintes fatores:<br \/>\u2022 Sele\u00e7\u00e3o de argumentos.<br \/>\u2022 Rela\u00e7\u00e3o de sentido entre as partes do texto.<br \/>\u2022 Progress\u00e3o tem\u00e1tica adequada ao desenvolvimento do tema, revelando que a reda\u00e7\u00e3o foi planejada e que as ideias desenvolvidas s\u00e3o, pouco a pouco, apresentadas, de forma organizada, em uma ordem l\u00f3gica.<br \/>\u2022 Desenvolvimento dos argumentos, com a explicita\u00e7\u00e3o da relev\u00e2ncia das ideias apresentadas para a defesa do ponto de vista definido.<\/p><\/blockquote>\n\n\n\n<p>A cartilha ainda orienta aos candidatos a fazerem um projeto de reda\u00e7\u00e3o! Isso n\u00e3o \u00e9 novidade para os nossos alunos, j\u00e1 que sempre fazemos essa recomenda\u00e7\u00e3o!<\/p>\n\n\n\n<p>Segundo a cartilha, projeto de texto \u00e9 o \u201cplanejamento pr\u00e9vio \u00e0 escrita da reda\u00e7\u00e3o. \u00c9 o esquema que se deixa perceber pela organiza\u00e7\u00e3o estrat\u00e9gica dos argumentos presentes no texto. \u00c9 nele que s\u00e3o definidos quais os argumentos que ser\u00e3o mobilizados para a defesa de sua tese, quais os momentos de introduzi-los e qual a melhor ordem para apresent\u00e1-los, de modo a garantir que o texto final seja articulado, claro e coerente\u201d.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>Na organiza\u00e7\u00e3o do texto dissertativo-argumentativo, voc\u00ea deve procurar atender \u00e0s seguintes exig\u00eancias:<br \/>\u2022 Apresenta\u00e7\u00e3o clara da tese e sele\u00e7\u00e3o dos argumentos que a sustentam.<br \/>\u2022 Encadeamento das ideias, de modo que cada par\u00e1grafo apresente informa\u00e7\u00f5es coerentes com o que foi apresentado anteriormente, sem repeti\u00e7\u00f5es ou saltos tem\u00e1ticos.<br \/>\u2022 Desenvolvimento dessas ideias por meio da explicita\u00e7\u00e3o, explica\u00e7\u00e3o ou exemplifica\u00e7\u00e3o das informa\u00e7\u00f5es, fatos e opini\u00f5es, de modo a justificar, para o leitor, o ponto de vista escolhido.<\/p><\/blockquote>\n\n\n\n<p>O quadro a seguir apresenta os seis n\u00edveis de desempenho que ser\u00e3o utilizados para avaliar a Compet\u00eancia 3 nas reda\u00e7\u00f5es do Enem 2019:<\/p>\n\n\n\n<p><strong>COMPET\u00caNCIA 3:<\/strong><\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter\"><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/redacao-enem-2019-cartilha-do-participante-o-que-mudou\/competencia-3\/\" rel=\"attachment wp-att-436058\"><img loading=\"lazy\" decoding=\"async\" width=\"586\" height=\"345\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2019\/10\/17125546\/Competencia-3.png.png\" alt=\"Competencia 3\" class=\"wp-image-436058\" srcset=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2019\/10\/17125546\/Competencia-3.png.png 586w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2019\/10\/17125546\/Competencia-3.png.png 300w\" sizes=\"auto, (max-width: 586px) 100vw, 586px\" \/><\/a><\/figure><\/div>\n\n\n\n<p><strong>COMPET\u00caNCIA 4<\/strong><br \/><strong>DEMONSTRAR CONHECIMENTO DOS MECANISMOS LINGU\u00cdSTICOS NECESS\u00c1RIOS PARA A CONSTRU\u00c7\u00c3O DA ARGUMENTA\u00c7\u00c3O<\/strong><\/p>\n\n\n\n<p>Existe uma estrutura l\u00f3gica e esperada para a reda\u00e7\u00e3o do ENEM. A compet\u00eancia 4 vai avaliar justamente essa estrutura. A organiza\u00e7\u00e3o textual \u00e9 muito importante e exige que as frases e os par\u00e1grafos estabele\u00e7am entre si uma rela\u00e7\u00e3o que garanta a sequencia\u00e7\u00e3o coerente do texto e a interdepend\u00eancia entre as ideias. N\u00e3o basta apenas colocar as ideias no texto, \u00e9 essencial articul\u00e1-las utilizando diversos recursos coesivos, em especial operadores argumentativos, que s\u00e3o respons\u00e1veis pelas rela\u00e7\u00f5es sem\u00e2nticas constru\u00eddas ao longo do texto, por exemplo, rela\u00e7\u00f5es de igualdade, de adversidade, de causa e consequ\u00eancia, de conclus\u00e3o, etc.<br \/>Quando falamos em coes\u00e3o textual, pensamos apenas em conjun\u00e7\u00f5es, mas as preposi\u00e7\u00f5es, conjun\u00e7\u00f5es, adv\u00e9rbios e locu\u00e7\u00f5es adverbiais tamb\u00e9m s\u00e3o respons\u00e1veis pela coes\u00e3o do texto, porque estabelecem uma inter-rela\u00e7\u00e3o entre ora\u00e7\u00f5es, frases e par\u00e1grafos. Cada par\u00e1grafo ser\u00e1 composto por um ou mais per\u00edodos tamb\u00e9m articulados; cada ideia nova precisa estabelecer rela\u00e7\u00e3o com as anteriores.<\/p>\n\n\n\n<p>A cartilha 2019 ressalta que \u201cas Compet\u00eancias 3 e 4 consideram a constru\u00e7\u00e3o da argumenta\u00e7\u00e3o ao longo do texto, por\u00e9m avaliam aspectos diferentes. Na Compet\u00eancia 3, \u00e9 avaliada a capacidade de o participante \u00b4selecionar, relacionar, organizar e interpretar informa\u00e7\u00f5es, fatos, opini\u00f5es e argumentos em defesa de um ponto de vista`, ou seja, trata-se da estrutura mais profunda do texto. J\u00e1 a coes\u00e3o, avaliada na Compet\u00eancia 4, atua na superf\u00edcie textual, isto \u00e9, avalia as marcas lingu\u00edsticas que ajudam a chegar \u00e0 compreens\u00e3o profunda do texto\u201d.<\/p>\n\n\n\n<p>Fique muito atento, ent\u00e3o, \u00e0 constru\u00e7\u00e3o de seu texto para demonstrar conhecimento sobre os mecanismos lingu\u00edsticos necess\u00e1rios para um adequado encadeamento textual, considerando os recursos coesivos que garantem a conex\u00e3o de ideias tanto entre os par\u00e1grafos quanto dentro deles.<\/p>\n\n\n\n<p>RECOMENDA\u00c7\u00d5ES DO PR\u00d3PRIO INEP:<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>\u2022 Procure utilizar as seguintes estrat\u00e9gias de coes\u00e3o para se referir a elementos que j\u00e1 apareceram no texto:<br \/>a) Substitui\u00e7\u00e3o de termos ou express\u00f5es por pronomes pessoais, possessivos e demonstrativos, adv\u00e9rbios que indicam localiza\u00e7\u00e3o, artigos.<br \/>b) Substitui\u00e7\u00e3o de termos ou express\u00f5es por sin\u00f4nimos, hip\u00f4nimos, hiper\u00f4nimos ou express\u00f5es resumitivas.<br \/>c) Substitui\u00e7\u00e3o de verbos, substantivos, per\u00edodos ou fragmentos do texto por conectivos ou express\u00f5es que retomem o que j\u00e1 foi dito.<br \/>d) Elipse ou omiss\u00e3o de elementos que j\u00e1 tenham sido citados ou que sejam facilmente identific\u00e1veis.<br \/>\u2022 Utilize operadores argumentativos para relacionar ora\u00e7\u00f5es, frases e par\u00e1grafos.<br \/>\u2022 Verifique se o elemento coesivo utilizado estabelece a rela\u00e7\u00e3o de sentido pretendida.<\/p><p>Resumindo: na elabora\u00e7\u00e3o da reda\u00e7\u00e3o, voc\u00ea deve evitar:<br \/>\u2022 Sequ\u00eancia justaposta de palavras e per\u00edodos sem articula\u00e7\u00e3o.<br \/>\u2022 Aus\u00eancia total de par\u00e1grafos na constru\u00e7\u00e3o do texto.<br \/>\u2022 Emprego de conector (preposi\u00e7\u00e3o, conjun\u00e7\u00e3o, pronome relativo, alguns adv\u00e9rbios e locu\u00e7\u00f5es adverbiais) que n\u00e3o estabele\u00e7a rela\u00e7\u00e3o l\u00f3gica entre dois trechos do texto e prejudique a compreens\u00e3o da mensagem.<br \/>\u2022 Repeti\u00e7\u00e3o ou substitui\u00e7\u00e3o inadequada de palavras sem se valer dos recursos oferecidos pela l\u00edngua (pronome, adv\u00e9rbio, artigo, sin\u00f4nimo).<\/p><\/blockquote>\n\n\n\n<p>Mais uma vez, vou usar a reda\u00e7\u00e3o retirada da cartilha do participando como exemplo de reda\u00e7\u00e3o dota mil para que voc\u00eas percebam a grande diversidade de elementos coesivos usados pela aluna!<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter\"><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/redacao-enem-2019-cartilha-do-participante-o-que-mudou\/exemplo-2-novo\/\" rel=\"attachment wp-att-436061\"><img loading=\"lazy\" decoding=\"async\" width=\"868\" height=\"1199\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2019\/10\/17130050\/Exemplo-2-novo.jpg\" alt=\"Exemplo 2\" class=\"wp-image-436061\" srcset=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2019\/10\/17130050\/Exemplo-2-novo.jpg 868w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2019\/10\/17130050\/Exemplo-2-novo.jpg 217w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2019\/10\/17130050\/Exemplo-2-novo.jpg 768w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2019\/10\/17130050\/Exemplo-2-novo.jpg 741w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2019\/10\/17130050\/Exemplo-2-novo.jpg 610w\" sizes=\"auto, (max-width: 868px) 100vw, 868px\" \/><\/a><\/figure><\/div>\n\n\n\n<p>Eu marquei em amarelo os elementos coesivos. Observem que ela praticamente n\u00e3o repetiu elementos e que eles garantiram sequ\u00eancia ao assunto tratado.<br \/>O quadro a seguir apresenta os seis n\u00edveis de desempenho que ser\u00e3o utilizados para avaliar a Compet\u00eancia 4 nas reda\u00e7\u00f5es do Enem 2019:<\/p>\n\n\n\n<p><strong>COMPET\u00caNCIA 4:<\/strong><\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter\"><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/redacao-enem-2019-cartilha-do-participante-o-que-mudou\/competencia-4\/\" rel=\"attachment wp-att-436059\"><img loading=\"lazy\" decoding=\"async\" width=\"590\" height=\"249\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2019\/10\/17125648\/Competencia-4.png.png\" alt=\"Competencia 4\" class=\"wp-image-436059\" srcset=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2019\/10\/17125648\/Competencia-4.png.png 590w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2019\/10\/17125648\/Competencia-4.png.png 300w\" sizes=\"auto, (max-width: 590px) 100vw, 590px\" \/><\/a><\/figure><\/div>\n\n\n\n<p><strong>COMPET\u00caNCIA 5<\/strong><br \/><strong>ELABORAR PROPOSTA DE INTERVEN\u00c7\u00c3O PARA O PROBLEMA ABORDADO, RESPEITANDO OS DIREITOS HUMANOS<\/strong><\/p>\n\n\n\n<p>O quinto aspecto a ser avaliado no seu texto \u00e9 muito importante, mas nem todos os alunos d\u00e3o a correta aten\u00e7\u00e3o a ele! N\u00e3o seja um desses alunos!<\/p>\n\n\n\n<p>A apresenta\u00e7\u00e3o de uma proposta de interven\u00e7\u00e3o para o problema abordado que respeite os direitos humanos \u00e9 fundamental para colocar \u201ca cereja do bolo\u201d em seu texto. Propor uma interven\u00e7\u00e3o para o problema apresentado pelo tema significa sugerir uma iniciativa que busque, mesmo que minimamente, enfrent\u00e1-lo.<br \/>Leia o que o pr\u00f3prio IMEP diz na cartilha do participante 2019: \u201c\u00c9 importante ressaltar que as provas de reda\u00e7\u00e3o do Enem normalmente abordam temas complexos, muitas vezes problemas de dif\u00edcil resolu\u00e7\u00e3o, de ordem social, cient\u00edfica, cultural ou pol\u00edtica. Por isso, voc\u00ea pode apresentar as mais diversas formas de interven\u00e7\u00e3o, desde uma sugest\u00e3o de combate at\u00e9 uma solu\u00e7\u00e3o efetiva da quest\u00e3o em foco\u201d.<\/p>\n\n\n\n<p>Ent\u00e3o ser\u00e1 a hora certa para demonstrar preparo para o exerc\u00edcio da cidadania, para atuar na realidade em conson\u00e2ncia com os direitos humanos. Voc\u00ea deve usar seus conhecimentos desenvolvidos ao longo de sua forma\u00e7\u00e3o para a produ\u00e7\u00e3o de um texto no qual, al\u00e9m de se posicionar de maneira cr\u00edtica e argumentar a favor de um ponto de vista, voc\u00ea possa indicar uma iniciativa que interfira no problema discutido em sua reda\u00e7\u00e3o.<br \/>A sua proposta precisa estar relacionada com a tese e com os argumentos, caso contr\u00e1rio, ela perde qualidade e sentido. Assim, \u00e9 necess\u00e1rio que a interven\u00e7\u00e3o apontada responda aos problemas discutidos por voc\u00ea, mostrando-se articulada ao seu projeto de texto.<\/p>\n\n\n\n<p>Sempre digo que a proposta de interven\u00e7\u00e3o precisa ser completa! Como assim, professora? Ao elaborar a sua interven\u00e7\u00e3o, voc\u00ea dever\u00e1 responder \u00e0s seguintes perguntas:<\/p>\n\n\n\n<p><span style=\"color: #3366ff;\"><em>1) O que \u00e9 poss\u00edvel apresentar como proposta de interven\u00e7\u00e3o para o problema?<\/em><\/span><br \/><span style=\"color: #3366ff;\"><em>2) Quem deve execut\u00e1-la?<\/em><\/span><br \/><span style=\"color: #3366ff;\"><em>3) Como viabilizar essa proposta?<\/em><\/span><br \/><span style=\"color: #3366ff;\"><em>4) Qual efeito ela pode alcan\u00e7ar?<\/em><\/span><br \/><span style=\"color: #3366ff;\"><em>5) Que outra informa\u00e7\u00e3o pode ser acrescentada para detalhar a proposta?<\/em><\/span><\/p>\n\n\n\n<p>Dessa forma, voc\u00ea far\u00e1 uma proposta eficiente e completa!<\/p>\n\n\n\n<p>O quadro a seguir apresenta os seis n\u00edveis de desempenho que ser\u00e3o utilizados para avaliar a Compet\u00eancia 5 nas reda\u00e7\u00f5es do Enem 2019:<\/p>\n\n\n\n<p><strong>COMPET\u00caNCIA 5:<\/strong><\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter\"><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/redacao-enem-2019-cartilha-do-participante-o-que-mudou\/competencia-5\/\" rel=\"attachment wp-att-436062\"><img loading=\"lazy\" decoding=\"async\" width=\"613\" height=\"285\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2019\/10\/17130135\/Competencia-5.png.png\" alt=\"Compet\u00eancia 5\" class=\"wp-image-436062\" srcset=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2019\/10\/17130135\/Competencia-5.png.png 613w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2019\/10\/17130135\/Competencia-5.png.png 300w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2019\/10\/17130135\/Competencia-5.png.png 610w\" sizes=\"auto, (max-width: 613px) 100vw, 613px\" \/><\/a><\/figure><\/div>\n\n\n\n<p>Conhe\u00e7a o nosso canal no YouTube e tenha acesso a v\u00e1rios conte\u00fados gratuitos:&nbsp;<a href=\"https:\/\/www.youtube.com\/channel\/UC7OnZODw1SNhfs0CDyVNTKg\" target=\"_blank\" rel=\"noopener noreferrer\">ESTRAT\u00c9GIA ENEM<\/a><\/p>\n\n\n\n<p>Quer saber como tirar nota MIL na reda\u00e7\u00e3o? <a href=\"https:\/\/www.youtube.com\/watch?v=Uykw4RDrM2g\" target=\"_blank\" rel=\"noopener noreferrer\">CLIQUE AQUI!<\/a><\/p>\n\n\n\n<p>Espero ter esclarecido muitas d\u00favidas!<br \/>No mais, fico \u00e0 disposi\u00e7\u00e3o!<\/p>\n\n\n\n<p>Forte abra\u00e7o.<br \/>Prof\u00aa Rafaela Freitas<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ol\u00e1, caros estudantes do ENEM! No \u00faltimo dia 10, o INEP lan\u00e7ou a cartilha de reda\u00e7\u00e3o ENEM (cartilha do participante 2019). N\u00f3s, do Estrat\u00e9gia ENEM, fizemos a leitura na \u00edntegra para compara\u00e7\u00e3o com a cartilha do ano passado (2018) e constatamos que n\u00e3o houve nenhuma altera\u00e7\u00e3o!Isso \u00e9 \u00f3timo, pois quer dizer que toda a prepara\u00e7\u00e3o [&hellip;]<\/p>\n","protected":false},"author":190,"featured_media":436063,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"post_tipo":"article","footnotes":""},"categories":[1],"tags":[128867,50662],"tax_estado":[],"class_list":["post-436025","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cursos-e-concursos","tag-cartilha-do-participante-enem-2019","tag-enem-2019"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.2 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Reda\u00e7\u00e3o ENEM 2019 - Cartilha do Participante - O que mudou?<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/redacao-enem-2019\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Reda\u00e7\u00e3o ENEM 2019 - Cartilha do Participante - O que mudou?\" \/>\n<meta property=\"og:description\" content=\"Ol\u00e1, caros estudantes do ENEM! No \u00faltimo dia 10, o INEP lan\u00e7ou a cartilha de reda\u00e7\u00e3o ENEM (cartilha do participante 2019). N\u00f3s, do Estrat\u00e9gia ENEM, fizemos a leitura na \u00edntegra para compara\u00e7\u00e3o com a cartilha do ano passado (2018) e constatamos que n\u00e3o houve nenhuma altera\u00e7\u00e3o!Isso \u00e9 \u00f3timo, pois quer dizer que toda a prepara\u00e7\u00e3o [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/redacao-enem-2019\/\" \/>\n<meta property=\"og:site_name\" content=\"Estrat\u00e9gia Concursos\" \/>\n<meta property=\"article:published_time\" content=\"2019-10-18T00:24:01+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-01-14T19:48:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2019\/10\/17130317\/Cartilha-do-Participante-REDA%C3%87%C3%83O-ENEM-2019.png\" \/>\n\t<meta property=\"og:image:width\" content=\"617\" \/>\n\t<meta property=\"og:image:height\" content=\"310\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Rafaela Freitas\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:site\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Rafaela Freitas\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"18 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/redacao-enem-2019\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/redacao-enem-2019\/\"},\"author\":{\"name\":\"Rafaela Freitas\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/b91f2c79fa09f992bd34e4182afb626c\"},\"headline\":\"Reda\u00e7\u00e3o ENEM 2019 &#8211; Cartilha do Participante &#8211; O que mudou?\",\"datePublished\":\"2019-10-18T00:24:01+00:00\",\"dateModified\":\"2021-01-14T19:48:22+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/redacao-enem-2019\/\"},\"wordCount\":3639,\"commentCount\":1,\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/redacao-enem-2019\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2019\/10\/17130317\/Cartilha-do-Participante-REDA%C3%87%C3%83O-ENEM-2019.png\",\"keywords\":[\"cartilha do participante enem 2019\",\"enem 2019\"],\"articleSection\":[\"Concursos P\u00fablicos\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/redacao-enem-2019\/#respond\"]}],\"copyrightYear\":\"2019\",\"copyrightHolder\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/redacao-enem-2019\/\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/redacao-enem-2019\/\",\"name\":\"Reda\u00e7\u00e3o ENEM 2019 - Cartilha do Participante - O que mudou?\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/redacao-enem-2019\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/redacao-enem-2019\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2019\/10\/17130317\/Cartilha-do-Participante-REDA%C3%87%C3%83O-ENEM-2019.png\",\"datePublished\":\"2019-10-18T00:24:01+00:00\",\"dateModified\":\"2021-01-14T19:48:22+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/redacao-enem-2019\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/redacao-enem-2019\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/redacao-enem-2019\/#primaryimage\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2019\/10\/17130317\/Cartilha-do-Participante-REDA%C3%87%C3%83O-ENEM-2019.png\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2019\/10\/17130317\/Cartilha-do-Participante-REDA%C3%87%C3%83O-ENEM-2019.png\",\"width\":617,\"height\":310,\"caption\":\"artilha do Participante - REDA\u00c7\u00c3O ENEM 2019\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/redacao-enem-2019\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Reda\u00e7\u00e3o ENEM 2019 &#8211; Cartilha do Participante &#8211; O que mudou?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"name\":\"Estrat\u00e9gia Concursos\",\"description\":\"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.\",\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\",\"name\":\"Estrat\u00e9gia Concursos\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"width\":230,\"height\":60,\"caption\":\"Estrat\u00e9gia Concursos\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/EstratConcursos\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/b91f2c79fa09f992bd34e4182afb626c\",\"name\":\"Rafaela Freitas\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/97ece78bdb320995d343d6c012a26475a2b8b6a591c52fbbd62c62640f68911e?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/97ece78bdb320995d343d6c012a26475a2b8b6a591c52fbbd62c62640f68911e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/97ece78bdb320995d343d6c012a26475a2b8b6a591c52fbbd62c62640f68911e?s=96&d=mm&r=g\",\"caption\":\"Rafaela Freitas\"},\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/rafaelafreitasestrategiaconcursos-com-br\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Reda\u00e7\u00e3o ENEM 2019 - Cartilha do Participante - O que mudou?","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.estrategiaconcursos.com.br\/blog\/redacao-enem-2019\/","og_locale":"pt_BR","og_type":"article","og_title":"Reda\u00e7\u00e3o ENEM 2019 - Cartilha do Participante - O que mudou?","og_description":"Ol\u00e1, caros estudantes do ENEM! No \u00faltimo dia 10, o INEP lan\u00e7ou a cartilha de reda\u00e7\u00e3o ENEM (cartilha do participante 2019). N\u00f3s, do Estrat\u00e9gia ENEM, fizemos a leitura na \u00edntegra para compara\u00e7\u00e3o com a cartilha do ano passado (2018) e constatamos que n\u00e3o houve nenhuma altera\u00e7\u00e3o!Isso \u00e9 \u00f3timo, pois quer dizer que toda a prepara\u00e7\u00e3o [&hellip;]","og_url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/redacao-enem-2019\/","og_site_name":"Estrat\u00e9gia Concursos","article_published_time":"2019-10-18T00:24:01+00:00","article_modified_time":"2021-01-14T19:48:22+00:00","og_image":[{"width":617,"height":310,"url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2019\/10\/17130317\/Cartilha-do-Participante-REDA%C3%87%C3%83O-ENEM-2019.png","type":"image\/png"}],"author":"Rafaela Freitas","twitter_card":"summary_large_image","twitter_creator":"@EstratConcursos","twitter_site":"@EstratConcursos","twitter_misc":{"Escrito por":"Rafaela Freitas","Est. tempo de leitura":"18 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/redacao-enem-2019\/#article","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/redacao-enem-2019\/"},"author":{"name":"Rafaela Freitas","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/b91f2c79fa09f992bd34e4182afb626c"},"headline":"Reda\u00e7\u00e3o ENEM 2019 &#8211; Cartilha do Participante &#8211; O que mudou?","datePublished":"2019-10-18T00:24:01+00:00","dateModified":"2021-01-14T19:48:22+00:00","mainEntityOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/redacao-enem-2019\/"},"wordCount":3639,"commentCount":1,"publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/redacao-enem-2019\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2019\/10\/17130317\/Cartilha-do-Participante-REDA%C3%87%C3%83O-ENEM-2019.png","keywords":["cartilha do participante enem 2019","enem 2019"],"articleSection":["Concursos P\u00fablicos"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/redacao-enem-2019\/#respond"]}],"copyrightYear":"2019","copyrightHolder":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/redacao-enem-2019\/","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/redacao-enem-2019\/","name":"Reda\u00e7\u00e3o ENEM 2019 - Cartilha do Participante - O que mudou?","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/redacao-enem-2019\/#primaryimage"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/redacao-enem-2019\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2019\/10\/17130317\/Cartilha-do-Participante-REDA%C3%87%C3%83O-ENEM-2019.png","datePublished":"2019-10-18T00:24:01+00:00","dateModified":"2021-01-14T19:48:22+00:00","breadcrumb":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/redacao-enem-2019\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/redacao-enem-2019\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/redacao-enem-2019\/#primaryimage","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2019\/10\/17130317\/Cartilha-do-Participante-REDA%C3%87%C3%83O-ENEM-2019.png","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2019\/10\/17130317\/Cartilha-do-Participante-REDA%C3%87%C3%83O-ENEM-2019.png","width":617,"height":310,"caption":"artilha do Participante - REDA\u00c7\u00c3O ENEM 2019"},{"@type":"BreadcrumbList","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/redacao-enem-2019\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.estrategiaconcursos.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Reda\u00e7\u00e3o ENEM 2019 &#8211; Cartilha do Participante &#8211; O que mudou?"}]},{"@type":"WebSite","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","name":"Estrat\u00e9gia Concursos","description":"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.","publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization","name":"Estrat\u00e9gia Concursos","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","width":230,"height":60,"caption":"Estrat\u00e9gia Concursos"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/EstratConcursos"]},{"@type":"Person","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/b91f2c79fa09f992bd34e4182afb626c","name":"Rafaela Freitas","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/97ece78bdb320995d343d6c012a26475a2b8b6a591c52fbbd62c62640f68911e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/97ece78bdb320995d343d6c012a26475a2b8b6a591c52fbbd62c62640f68911e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/97ece78bdb320995d343d6c012a26475a2b8b6a591c52fbbd62c62640f68911e?s=96&d=mm&r=g","caption":"Rafaela Freitas"},"url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/rafaelafreitasestrategiaconcursos-com-br\/"}]}},"_links":{"self":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/436025","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/users\/190"}],"replies":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/comments?post=436025"}],"version-history":[{"count":13,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/436025\/revisions"}],"predecessor-version":[{"id":650767,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/436025\/revisions\/650767"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media\/436063"}],"wp:attachment":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media?parent=436025"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/categories?post=436025"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tags?post=436025"},{"taxonomy":"tax_estado","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tax_estado?post=436025"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}