{"id":433409,"date":"2019-10-13T17:32:21","date_gmt":"2019-10-13T20:32:21","guid":{"rendered":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?p=433409"},"modified":"2019-11-08T16:34:38","modified_gmt":"2019-11-08T19:34:38","slug":"comentarios-as-questoes-de-acessibilidade-do-tj-am","status":"publish","type":"post","link":"https:\/\/www.estrategiaconcursos.com.br\/blog\/comentarios-as-questoes-de-acessibilidade-do-tj-am\/","title":{"rendered":"Coment\u00e1rios \u00e0s quest\u00f5es de Acessibilidade do TJ-AM"},"content":{"rendered":"\n<p>Ol\u00e1! Analisamos as quest\u00f5es de Acessibilidade aplicadas na prova deste final de semana do TJ-AM. Verificamos as quest\u00f5es e entendemos que n\u00e3o cabe recurso em uma an\u00e1lise preliminar. N\u00e3o obstante, caso voc\u00ea fique em d\u00favida, por favor, nos contate:<\/p>\n\n\n\n<p>INSTAGRAM:&nbsp;<a href=\"https:\/\/www.instagram.com\/proftorques\/\">https:\/\/www.instagram.com\/proftorques\/<\/a><\/p>\n\n\n\n<p>TELEGRAM: <a href=\"https:\/\/t.me\/dpcparaconcursos\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\"https:\/\/t.me\/dpcparaconcursos (abre numa nova aba)\">https:\/\/t.me\/dpcparaconcursos<\/a><\/p>\n\n\n\n<p>Vamos \u00e0s quest\u00f5es?!<\/p>\n\n\n\n<p><strong>ANALISTA JUDICI\u00c1RIO &#8211; ESPECIALIDADE DIREITO<\/strong><\/p>\n\n\n\n<p>&#8212;<\/p>\n\n\n\n<p><strong>28.<\/strong> (CESPE\/TJAM\/2019) Ainda com base na legisla\u00e7\u00e3o\ninstitucional e na legisla\u00e7\u00e3o do Poder Judici\u00e1rio do estado do Amazonas, julgue\nos itens seguintes.<\/p>\n\n\n\n<p>Todo \u00f3rg\u00e3o do Poder Judici\u00e1rio deve possuir, em seu quadro de pessoal, servidores, efetivos e(ou) terceirizados, capacitados para usar e interpretar a l\u00edngua brasileira de sinais (LIBRAS). <\/p>\n\n\n\n<p><strong>Coment\u00e1rios<\/strong><\/p>\n\n\n\n<p>Assertiva <strong>correta<\/strong>, com fundamento no art. 5\u00ba, \u00a72\u00ba, da Res.\nCNJ 230\/2016. Embora a quest\u00e3o n\u00e3o tenha mencionado o percentual de 5%, h\u00e1\nrefer\u00eancia gen\u00e9rica \u00e0 obrigatoriedade de servidores capacitados para uso e\ninterpreta\u00e7\u00e3o de Libras.<\/p>\n\n\n\n<p>&#8212;<\/p>\n\n\n\n<p><strong>30.<\/strong> (CESPE\/TJAM\/2019) Julgue os itens a seguir, tendo\ncomo refer\u00eancia a Lei Brasileira de Inclus\u00e3o da Pessoa com Defici\u00eancia (Lei n\u00ba\n13.146\/2015).<\/p>\n\n\n\n<p>Nos programas habitacionais p\u00fablicos, pessoas com\ndefici\u00eancia t\u00eam prioridade de aquisi\u00e7\u00e3o de im\u00f3vel para moradia pr\u00f3pria, com\nreserva de percentual m\u00ednimo legal de unidades para elas. <\/p>\n\n\n\n<p><strong>Coment\u00e1rios<\/strong><\/p>\n\n\n\n<p>A assertiva est\u00e1 <strong>correta<\/strong>, conforme o art. 32, da Lei\n13.146\/2015. Tal percentual \u00e9 de 3%:<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>Art. 32. Nos programas habitacionais, p\u00fablicos ou subsidiados com recursos p\u00fablicos, a pessoa com defici\u00eancia ou o seu respons\u00e1vel goza de prioridade na aquisi\u00e7\u00e3o de im\u00f3vel para moradia pr\u00f3pria, observado o seguinte:<\/p><p>I &#8211; reserva de, no m\u00ednimo, 3% (tr\u00eas por cento) das unidades habitacionais para pessoa com defici\u00eancia;<\/p><\/blockquote>\n\n\n\n<p>&#8212;<\/p>\n\n\n\n<p><strong>31.<\/strong> (CESPE\/TJAM\/2019) Barreiras arquitet\u00f4nicas \u00e9 a\ndesigna\u00e7\u00e3o dada \u00e0s barreiras existentes em vias e espa\u00e7os p\u00fablicos e privados\nabertos ao p\u00fablico ou de uso coletivo. <\/p>\n\n\n\n<p><strong>Coment\u00e1rios<\/strong><\/p>\n\n\n\n<p>A assertiva est\u00e1 <strong>incorreta<\/strong>,\npois traz o conceito de barreira urban\u00edstica. Vejamos o art. 3\u00ba, IV, \u201ca\u201d e \u201cb\u201d,\nda Lei de Inclus\u00e3o, que trazem esses conceitos:<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>Art. 3\u00ba Para fins de aplica\u00e7\u00e3o desta Lei, consideram-se:<\/p><p>IV &#8211; barreiras: qualquer entrave, obst\u00e1culo, atitude ou comportamento que limite ou impe\u00e7a a participa\u00e7\u00e3o social da pessoa, bem como o gozo, a frui\u00e7\u00e3o e o exerc\u00edcio de seus direitos \u00e0 acessibilidade, \u00e0 liberdade de movimento e de express\u00e3o, \u00e0 comunica\u00e7\u00e3o, ao acesso \u00e0 informa\u00e7\u00e3o, \u00e0 compreens\u00e3o, \u00e0 circula\u00e7\u00e3o com seguran\u00e7a, entre outros, classificadas em:<\/p><p>a)<strong> barreiras urban\u00edsticas<\/strong>: as existentes nas vias e nos espa\u00e7os p\u00fablicos e privados abertos ao p\u00fablico ou de uso coletivo;<\/p><p>b) <strong>barreiras arquitet\u00f4nicas<\/strong>: as existentes nos edif\u00edcios p\u00fablicos e privados;<\/p><\/blockquote>\n\n\n\n<p>&#8212;<\/p>\n\n\n\n<p><strong>32.<\/strong> (CESPE\/TJAM\/2019) As institui\u00e7\u00f5es privadas de\nensino, assim como as p\u00fablicas, devem ofertar educa\u00e7\u00e3o bilingue em l\u00edngua\nbrasileira de sinais (LIBRAS) e l\u00edngua portuguesa. <\/p>\n\n\n\n<p><strong>Coment\u00e1rios<\/strong><\/p>\n\n\n\n<p>A alterativa est\u00e1 <strong>incorreta<\/strong>,\npois essa obrigatoriedade n\u00e3o se estende \u00e0s escolas privadas. O art. 28, IV, da\nLei 13.146\/2015 traz essa previs\u00e3o:<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>Art. 28. Incumbe ao poder p\u00fablico assegurar, criar, desenvolver, implementar, incentivar, acompanhar e avaliar:<\/p><p>IV &#8211; oferta de educa\u00e7\u00e3o bil\u00edngue, em Libras como primeira l\u00edngua e na modalidade escrita da l\u00edngua portuguesa como segunda l\u00edngua, em escolas e classes bil\u00edngues e em escolas inclusivas;<\/p><\/blockquote>\n\n\n\n<p>Contudo, o \u00a71\u00ba, que estende essas obriga\u00e7\u00f5es \u00e0s escolas\nprivadas, n\u00e3o traz o inciso IV, de modo que n\u00e3o \u00e9 obrigat\u00f3rio para escolas\nprivadas:<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>\u00a7 1\u00ba \u00c0s institui\u00e7\u00f5es privadas, de qualquer n\u00edvel e modalidade de ensino, aplica-se obrigatoriamente o disposto nos incisos I, II, III, V, VII, VIII, IX, X, XI, XII, XIII, XIV, XV, XVI, XVII e XVIII do caput deste artigo, sendo vedada a cobran\u00e7a de valores adicionais de qualquer natureza em suas mensalidades, anuidades e matr\u00edculas no cumprimento dessas determina\u00e7\u00f5es.<\/p><\/blockquote>\n\n\n\n<p>&#8212;<\/p>\n\n\n\n<p><strong>33.<\/strong> (CESPE\/TJAM\/2019)Eventual benef\u00edcio\ndecorrente de a\u00e7\u00e3o afirmativa n\u00e3o pode ser imposto a pessoa com defici\u00eancia: a\nela cabe decidir sobre a frui\u00e7\u00e3o desse benef\u00edcio. <\/p>\n\n\n\n<p><strong>Coment\u00e1rios<\/strong><\/p>\n\n\n\n<p>A assertiva est\u00e1 <strong>correta<\/strong>. Vejamos o art. 4\u00ba, \u00a72\u00ba, da lei\nde Inclus\u00e3o da Pessoa com Defici\u00eancia:<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>Art. 4\u00ba Toda pessoa com defici\u00eancia tem direito \u00e0 igualdade de oportunidades com as demais pessoas e n\u00e3o sofrer\u00e1 nenhuma esp\u00e9cie de discrimina\u00e7\u00e3o.<\/p><p>\u00a7 2\u00ba A pessoa com defici\u00eancia n\u00e3o est\u00e1 obrigada \u00e0 frui\u00e7\u00e3o de benef\u00edcios decorrentes de a\u00e7\u00e3o afirmativa.<\/p><\/blockquote>\n\n\n\n<p>&#8212;<\/p>\n\n\n\n<p><strong>34.<\/strong> (CESPE\/TJAM\/2019) Os servi\u00e7os socioassistenciais\npara pessoa com defici\u00eancia em situa\u00e7\u00e3o de depend\u00eancia incluem a presta\u00e7\u00e3o de\ncuidados b\u00e1sicos e instrumentais por cuidadores sociais. <\/p>\n\n\n\n<p><strong>Coment\u00e1rios<\/strong><\/p>\n\n\n\n<p>A assertiva est\u00e1 <strong>correta<\/strong>, pois traz o que prescreve o \u00a72\u00ba\ndo art. 39 da Lei 13.46\/2015:<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>Art. 39. Os servi\u00e7os, os programas, os projetos e os benef\u00edcios no \u00e2mbito da pol\u00edtica p\u00fablica de assist\u00eancia social \u00e0 pessoa com defici\u00eancia e sua fam\u00edlia t\u00eam como objetivo a garantia da seguran\u00e7a de renda, da acolhida, da habilita\u00e7\u00e3o e da reabilita\u00e7\u00e3o, do desenvolvimento da autonomia e da conviv\u00eancia familiar e comunit\u00e1ria, para a promo\u00e7\u00e3o do acesso a direitos e da plena participa\u00e7\u00e3o social.<\/p><p>\u00a7 2\u00ba Os servi\u00e7os socioassistenciais destinados \u00e0 pessoa com defici\u00eancia em situa\u00e7\u00e3o de depend\u00eancia dever\u00e3o contar com <strong>cuidadores sociais <\/strong>para prestar-lhe <strong>cuidados b\u00e1sicos e instrumentais.<\/strong><\/p><\/blockquote>\n\n\n\n<p>&#8212;<\/p>\n\n\n\n<p><strong>ASSISTENTE JUDICI\u00c1RIO<\/strong><\/p>\n\n\n\n<p><strong>28.<\/strong> (CESPE\/TJAM\/2019) Ainda tendo como refer\u00eancia\nlegisla\u00e7\u00e3o institucional e a do Poder Judici\u00e1rio do Estado do Amazonas, julgue\nos itens subsequentes.<\/p>\n\n\n\n<p>Pessoa com defici\u00eancia e seu acompanhante t\u00eam direito a\natendimento priorit\u00e1rio na tramita\u00e7\u00e3o processual em que forem partes os\ninteressados, nos atos e nas dilig\u00eancias.<\/p>\n\n\n\n<p><strong>Coment\u00e1rios<\/strong><\/p>\n\n\n\n<p>A assertiva est\u00e1 <strong>incorreta<\/strong>,\npois embora a pessoa com defici\u00eancia tenha esse direito, ele n\u00e3o \u00e9 extens\u00edvel ao\nseu acompanhante. Vejamos o art. 9\u00ba, VII, do EPD:<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>Art. 9\u00ba A pessoa com defici\u00eancia tem direito a receber atendimento priorit\u00e1rio, sobretudo com a finalidade de:<\/p><p>VII &#8211; tramita\u00e7\u00e3o processual e procedimentos judiciais e administrativos em que for parte ou interessada, em todos os atos e dilig\u00eancias.<\/p><p>\u00a7 1\u00ba Os direitos previstos neste artigo s\u00e3o extensivos ao acompanhante da pessoa com defici\u00eancia ou ao seu atendente pessoal, exceto quanto ao disposto nos incisos VI e VII deste artigo.<\/p><\/blockquote>\n\n\n\n<p>&#8212;<\/p>\n\n\n\n<p><strong>30.<\/strong> (CESPE\/TJAM\/2019) Com base na Lei 13.146\/2015(Lei brasileira de inclus\u00e3o da Pessoa com defici\u00eancia) E em suas altera\u00e7\u00f5es, julgue os itens a seguir.<\/p>\n\n\n\n<p>Se uma pessoa com defici\u00eancia tiver de se submeter a interven\u00e7\u00e3o\ncl\u00ednica ou cir\u00fargica, o consentimento dela ser\u00e1 imprescind\u00edvel para a\nrealiza\u00e7\u00e3o dos procedimentos e, por isso, n\u00e3o poder\u00e1 ser suprido, ainda que ela\nesteja em situa\u00e7\u00e3o de curatela.<\/p>\n\n\n\n<p><strong>Coment\u00e1rios<\/strong><\/p>\n\n\n\n<p>A assertiva est\u00e1 <strong>incorreta<\/strong>,\npois o consentimento poder\u00e1 ser suprido no caso de curatela. Vejamos o art. 11,\nda Lei 13.146\/2015. <\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>Art. 11. A pessoa com defici\u00eancia n\u00e3o poder\u00e1 ser obrigada a se submeter a interven\u00e7\u00e3o cl\u00ednica ou cir\u00fargica, a tratamento ou a institucionaliza\u00e7\u00e3o for\u00e7ada.<\/p><p>Par\u00e1grafo \u00fanico. O consentimento da pessoa com defici\u00eancia em situa\u00e7\u00e3o de curatela poder\u00e1 ser suprido, na forma da lei.<\/p><\/blockquote>\n\n\n\n<p>&#8212;<\/p>\n\n\n\n<p><strong>31.<\/strong> (CESPE\/TJAM\/2019) Cabe ao Poder P\u00fablico assegurar a produ\u00e7\u00e3o de artigos cient\u00edficos em formato acess\u00edvel, inclusive em l\u00edngua brasileira de sinais (LIBRAS), pelas institui\u00e7\u00f5es p\u00fablicas de ensino e pesquisa.<\/p>\n\n\n\n<p><strong>Coment\u00e1rios<\/strong><\/p>\n\n\n\n<p>A assertiva est\u00e1 <strong>incorreta<\/strong>,\npois o poder p\u00fablico deve estimular e apoiar a produ\u00e7\u00e3o de artigos cient\u00edficos\nem Libras, mas n\u00e3o se fala em obrigatoriedade. Veja o art. 68, \u00a73\u00ba, da Lei 13.146\/2015:<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>\u00a7 3\u00ba O poder p\u00fablico deve estimular e apoiar a adapta\u00e7\u00e3o e a produ\u00e7\u00e3o de artigos cient\u00edficos em formato acess\u00edvel, inclusive em Libras.<\/p><\/blockquote>\n\n\n\n<p>&#8212;<\/p>\n\n\n\n<p><strong>32.<\/strong> (CESPE\/TJAM\/2019) Para que um indiv\u00edduo seja considerado pessoa com defici\u00eancia, ele deve ter algum impedimento de longo prazo, que pode ser de natureza intelectual.<\/p>\n\n\n\n<p><strong>Coment\u00e1rios<\/strong><\/p>\n\n\n\n<p>A assertiva est\u00e1 <strong>correta<\/strong>. A defici\u00eancia deve ser de longo\nprazo e pode ser de natureza intelectual ou de outra natureza, mas pode ser\napenas intelectual. Vejamos o art. 2\u00ba, do EPD:<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>Art. 2\u00ba Considera-se pessoa com defici\u00eancia aquela que tem impedimento de longo prazo de natureza f\u00edsica, mental, intelectual ou sensorial, o qual, em intera\u00e7\u00e3o com uma ou mais barreiras, pode obstruir sua participa\u00e7\u00e3o plena e efetiva na sociedade em igualdade de condi\u00e7\u00f5es com as demais pessoas.<\/p><\/blockquote>\n\n\n\n<p>&#8212;<\/p>\n\n\n\n<p><strong>33.<\/strong> (CESPE\/TJAM\/2019) A pessoa com defici\u00eancia tem plena capacidade civil para exercer o direito a fam\u00edlia, exercer seus direitos sexuais e conservar sua fertilidade, sendo vedada a esteriliza\u00e7\u00e3o compuls\u00f3ria.<\/p>\n\n\n\n<p><strong>Coment\u00e1rios<\/strong><\/p>\n\n\n\n<p>A assertiva est\u00e1 <strong>correta<\/strong>. Vejamos o art. 6\u00ba, da Lei de\nInclus\u00e3o:<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>Art. 6\u00ba A defici\u00eancia n\u00e3o afeta a plena capacidade civil da pessoa, inclusive para:<\/p><p>I &#8211; casar-se e constituir uni\u00e3o est\u00e1vel;<\/p><p>II &#8211; exercer direitos sexuais e reprodutivos;<\/p><p>III &#8211; exercer o direito de decidir sobre o n\u00famero de filhos e de ter acesso a informa\u00e7\u00f5es adequadas sobre reprodu\u00e7\u00e3o e planejamento familiar;<\/p><p>IV &#8211; conservar sua fertilidade, sendo vedada a esteriliza\u00e7\u00e3o compuls\u00f3ria;<\/p><\/blockquote>\n\n\n\n<p>A quest\u00e3o fala em direitos \u00e0 fam\u00edlia, que inclui o direito\nde casar-se e decidir sobre os filhos. <\/p>\n\n\n\n<p>Ademais, \u00e9 vedada a esteriliza\u00e7\u00e3o compuls\u00f3ria. <\/p>\n\n\n\n<p>&#8212;<\/p>\n\n\n\n<p><strong>34.<\/strong> (CESPE\/TJAM\/2019) \u00c9 vedado ao juiz nomear, de of\u00edcio, curador da\nPessoa com defici\u00eancia em situa\u00e7\u00e3o de curatela.<\/p>\n\n\n\n<p><strong>Coment\u00e1rios<\/strong><\/p>\n\n\n\n<p>A assertiva est\u00e1 <strong>incorreta<\/strong>. Em caso de relev\u00e2ncia e urg\u00eancia, e\nouvido o MP, \u00e9 poss\u00edvel a nomea\u00e7\u00e3o de curador provis\u00f3rio de of\u00edcio. <\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>Art. 87. Em <strong>casos de relev\u00e2ncia e urg\u00eancia <\/strong>e a fim de proteger os interesses da pessoa com defici\u00eancia em situa\u00e7\u00e3o de curatela, ser\u00e1 l\u00edcito ao juiz, ouvido o Minist\u00e9rio P\u00fablico, de oficio ou a requerimento do interessado, nomear, desde logo, curador provis\u00f3rio, o qual estar\u00e1 sujeito, no que couber, \u00e0s disposi\u00e7\u00f5es do C\u00f3digo de Processo Civil .<\/p><\/blockquote>\n\n\n\n<p>&#8212;<\/p>\n\n\n\n<p>\u00c9 isso. <\/p>\n\n\n\n<p>Bons estudos!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ol\u00e1! Analisamos as quest\u00f5es de Acessibilidade aplicadas na prova deste final de semana do TJ-AM. Verificamos as quest\u00f5es e entendemos que n\u00e3o cabe recurso em uma an\u00e1lise preliminar. N\u00e3o obstante, caso voc\u00ea fique em d\u00favida, por favor, nos contate: INSTAGRAM:&nbsp;https:\/\/www.instagram.com\/proftorques\/ TELEGRAM: https:\/\/t.me\/dpcparaconcursos Vamos \u00e0s quest\u00f5es?! ANALISTA JUDICI\u00c1RIO &#8211; ESPECIALIDADE DIREITO &#8212; 28. (CESPE\/TJAM\/2019) Ainda com [&hellip;]<\/p>\n","protected":false},"author":180,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"post_tipo":"article","footnotes":""},"categories":[1,1984],"tags":[126752,3705,867,671],"tax_estado":[],"class_list":["post-433409","post","type-post","status-publish","format-standard","hentry","category-cursos-e-concursos","category-tribunais","tag-acessbilidade","tag-pessoa-com-deficiencia","tag-prova-comentada","tag-tj-am"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.2 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Coment\u00e1rios \u00e0s quest\u00f5es de Acessibilidade do TJ-AM<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/comentarios-as-questoes-de-acessibilidade-do-tj-am\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Coment\u00e1rios \u00e0s quest\u00f5es de Acessibilidade do TJ-AM\" \/>\n<meta property=\"og:description\" content=\"Ol\u00e1! Analisamos as quest\u00f5es de Acessibilidade aplicadas na prova deste final de semana do TJ-AM. Verificamos as quest\u00f5es e entendemos que n\u00e3o cabe recurso em uma an\u00e1lise preliminar. N\u00e3o obstante, caso voc\u00ea fique em d\u00favida, por favor, nos contate: INSTAGRAM:&nbsp;https:\/\/www.instagram.com\/proftorques\/ TELEGRAM: https:\/\/t.me\/dpcparaconcursos Vamos \u00e0s quest\u00f5es?! ANALISTA JUDICI\u00c1RIO &#8211; ESPECIALIDADE DIREITO &#8212; 28. (CESPE\/TJAM\/2019) Ainda com [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/comentarios-as-questoes-de-acessibilidade-do-tj-am\/\" \/>\n<meta property=\"og:site_name\" content=\"Estrat\u00e9gia Concursos\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/ricardo.s.torques\" \/>\n<meta property=\"article:published_time\" content=\"2019-10-13T20:32:21+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-11-08T19:34:38+00:00\" \/>\n<meta name=\"author\" content=\"Ricardo Torques\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:site\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ricardo Torques\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/comentarios-as-questoes-de-acessibilidade-do-tj-am\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/comentarios-as-questoes-de-acessibilidade-do-tj-am\/\"},\"author\":{\"name\":\"Ricardo Torques\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/aa39cf5ddb518e5bdce27c35788405e2\"},\"headline\":\"Coment\u00e1rios \u00e0s quest\u00f5es de Acessibilidade do TJ-AM\",\"datePublished\":\"2019-10-13T20:32:21+00:00\",\"dateModified\":\"2019-11-08T19:34:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/comentarios-as-questoes-de-acessibilidade-do-tj-am\/\"},\"wordCount\":1689,\"commentCount\":2,\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"keywords\":[\"acessbilidade\",\"pessoa com defici\u00eancia\",\"prova comentada\",\"TJ-AM\"],\"articleSection\":[\"Concursos P\u00fablicos\",\"Tribunais\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/comentarios-as-questoes-de-acessibilidade-do-tj-am\/#respond\"]}],\"copyrightYear\":\"2019\",\"copyrightHolder\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/comentarios-as-questoes-de-acessibilidade-do-tj-am\/\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/comentarios-as-questoes-de-acessibilidade-do-tj-am\/\",\"name\":\"Coment\u00e1rios \u00e0s quest\u00f5es de Acessibilidade do TJ-AM\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\"},\"datePublished\":\"2019-10-13T20:32:21+00:00\",\"dateModified\":\"2019-11-08T19:34:38+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/comentarios-as-questoes-de-acessibilidade-do-tj-am\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/comentarios-as-questoes-de-acessibilidade-do-tj-am\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/comentarios-as-questoes-de-acessibilidade-do-tj-am\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Coment\u00e1rios \u00e0s quest\u00f5es de Acessibilidade do TJ-AM\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"name\":\"Estrat\u00e9gia Concursos\",\"description\":\"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.\",\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\",\"name\":\"Estrat\u00e9gia Concursos\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"width\":230,\"height\":60,\"caption\":\"Estrat\u00e9gia Concursos\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/EstratConcursos\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/aa39cf5ddb518e5bdce27c35788405e2\",\"name\":\"Ricardo Torques\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/ce9ac6c3cff25fe86d15ed568ebc64d1724baf5c0693133bcb1f6073f712f92a?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/ce9ac6c3cff25fe86d15ed568ebc64d1724baf5c0693133bcb1f6073f712f92a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/ce9ac6c3cff25fe86d15ed568ebc64d1724baf5c0693133bcb1f6073f712f92a?s=96&d=mm&r=g\",\"caption\":\"Ricardo Torques\"},\"sameAs\":[\"https:\/\/www.facebook.com\/ricardo.s.torques\"],\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/ricardotorquesestrategiaconcursos-com-br\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Coment\u00e1rios \u00e0s quest\u00f5es de Acessibilidade do TJ-AM","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.estrategiaconcursos.com.br\/blog\/comentarios-as-questoes-de-acessibilidade-do-tj-am\/","og_locale":"pt_BR","og_type":"article","og_title":"Coment\u00e1rios \u00e0s quest\u00f5es de Acessibilidade do TJ-AM","og_description":"Ol\u00e1! Analisamos as quest\u00f5es de Acessibilidade aplicadas na prova deste final de semana do TJ-AM. Verificamos as quest\u00f5es e entendemos que n\u00e3o cabe recurso em uma an\u00e1lise preliminar. N\u00e3o obstante, caso voc\u00ea fique em d\u00favida, por favor, nos contate: INSTAGRAM:&nbsp;https:\/\/www.instagram.com\/proftorques\/ TELEGRAM: https:\/\/t.me\/dpcparaconcursos Vamos \u00e0s quest\u00f5es?! ANALISTA JUDICI\u00c1RIO &#8211; ESPECIALIDADE DIREITO &#8212; 28. (CESPE\/TJAM\/2019) Ainda com [&hellip;]","og_url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/comentarios-as-questoes-de-acessibilidade-do-tj-am\/","og_site_name":"Estrat\u00e9gia Concursos","article_author":"https:\/\/www.facebook.com\/ricardo.s.torques","article_published_time":"2019-10-13T20:32:21+00:00","article_modified_time":"2019-11-08T19:34:38+00:00","author":"Ricardo Torques","twitter_card":"summary_large_image","twitter_creator":"@EstratConcursos","twitter_site":"@EstratConcursos","twitter_misc":{"Escrito por":"Ricardo Torques","Est. tempo de leitura":"8 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/comentarios-as-questoes-de-acessibilidade-do-tj-am\/#article","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/comentarios-as-questoes-de-acessibilidade-do-tj-am\/"},"author":{"name":"Ricardo Torques","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/aa39cf5ddb518e5bdce27c35788405e2"},"headline":"Coment\u00e1rios \u00e0s quest\u00f5es de Acessibilidade do TJ-AM","datePublished":"2019-10-13T20:32:21+00:00","dateModified":"2019-11-08T19:34:38+00:00","mainEntityOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/comentarios-as-questoes-de-acessibilidade-do-tj-am\/"},"wordCount":1689,"commentCount":2,"publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"keywords":["acessbilidade","pessoa com defici\u00eancia","prova comentada","TJ-AM"],"articleSection":["Concursos P\u00fablicos","Tribunais"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/comentarios-as-questoes-de-acessibilidade-do-tj-am\/#respond"]}],"copyrightYear":"2019","copyrightHolder":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/comentarios-as-questoes-de-acessibilidade-do-tj-am\/","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/comentarios-as-questoes-de-acessibilidade-do-tj-am\/","name":"Coment\u00e1rios \u00e0s quest\u00f5es de Acessibilidade do TJ-AM","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website"},"datePublished":"2019-10-13T20:32:21+00:00","dateModified":"2019-11-08T19:34:38+00:00","breadcrumb":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/comentarios-as-questoes-de-acessibilidade-do-tj-am\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/comentarios-as-questoes-de-acessibilidade-do-tj-am\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/comentarios-as-questoes-de-acessibilidade-do-tj-am\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.estrategiaconcursos.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Coment\u00e1rios \u00e0s quest\u00f5es de Acessibilidade do TJ-AM"}]},{"@type":"WebSite","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","name":"Estrat\u00e9gia Concursos","description":"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.","publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization","name":"Estrat\u00e9gia Concursos","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","width":230,"height":60,"caption":"Estrat\u00e9gia Concursos"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/EstratConcursos"]},{"@type":"Person","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/aa39cf5ddb518e5bdce27c35788405e2","name":"Ricardo Torques","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/ce9ac6c3cff25fe86d15ed568ebc64d1724baf5c0693133bcb1f6073f712f92a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ce9ac6c3cff25fe86d15ed568ebc64d1724baf5c0693133bcb1f6073f712f92a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ce9ac6c3cff25fe86d15ed568ebc64d1724baf5c0693133bcb1f6073f712f92a?s=96&d=mm&r=g","caption":"Ricardo Torques"},"sameAs":["https:\/\/www.facebook.com\/ricardo.s.torques"],"url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/ricardotorquesestrategiaconcursos-com-br\/"}]}},"_links":{"self":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/433409","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/users\/180"}],"replies":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/comments?post=433409"}],"version-history":[{"count":3,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/433409\/revisions"}],"predecessor-version":[{"id":433494,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/433409\/revisions\/433494"}],"wp:attachment":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media?parent=433409"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/categories?post=433409"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tags?post=433409"},{"taxonomy":"tax_estado","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tax_estado?post=433409"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}