{"id":406610,"date":"2019-08-06T12:20:47","date_gmt":"2019-08-06T15:20:47","guid":{"rendered":"https:\/\/blog-estrategia.mystagingwebsite.com\/blog\/?p=406610"},"modified":"2019-11-08T17:44:26","modified_gmt":"2019-11-08T20:44:26","slug":"concurso-prefeitura-de-rio-preto-sp-retificacao-altera-valor-de-remuneracao","status":"publish","type":"post","link":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-prefeitura-de-rio-preto-sp-retificacao-altera-valor-de-remuneracao\/","title":{"rendered":"Concurso Prefeitura de Rio Preto SP: Retifica\u00e7\u00e3o altera valor de remunera\u00e7\u00e3o"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Foi publicada a primeira retifica\u00e7\u00e3o de um dos editais para o concurso da Prefeitura de S\u00e3o Jos\u00e9 do Rio Preto, munic\u00edpio de S\u00e3o Paulo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nos primeiros dias de agosto foram publicados 05 editais, com um total de 349 vagas, para diversas \u00e1reas e n\u00edveis de forma\u00e7\u00e3o.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hoje, 06 de agosto, foi publicada uma retifica\u00e7\u00e3o alterando o valor da remunera\u00e7\u00e3o inicial do cargo de <strong><em>M\u00e9dico do Trabalho<\/em><\/strong>, que anteriormente ofertava uma remunera\u00e7\u00e3o de mais de R$8 mil, al\u00e9m dos benef\u00edcios.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Agora, a remunera\u00e7\u00e3o inicial ser\u00e1 no valor de <strong>R$ 4.125,92<\/strong>, somada aos aux\u00edlios alimenta\u00e7\u00e3o (R$ 400,00) e sa\u00fade (R$ 350,00), totalizando R$4.875,92.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Os editais do concurso de Rio Preto<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">A Funda\u00e7\u00e3o Carlos Chagas &#8211; FCC \u00e9 a respons\u00e1vel pela coordena\u00e7\u00e3o e  realiza\u00e7\u00e3o deste certame.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Com 349 vagas, o certame traz oportunidades para diversas \u00e1reas e n\u00edveis de forma\u00e7\u00e3o, conforme voc\u00ea v\u00ea abaixo:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><em><strong>Agente de Combate \u00e0s Endemias<\/strong><\/em><strong> <\/strong>&#8211;<em><strong> 60 vagas  <\/strong><\/em>&#8211; R$ 1.550,06 + R$ 350,00 (aux\u00edlio-sa\u00fade) + R$ 400,00* (aux\u00edlio-alimenta\u00e7\u00e3o).<\/li><li><em><strong>Agente Comunit\u00e1rio de Sa\u00fade <\/strong><\/em>&#8211;<strong><em> 80 vagas<\/em><\/strong> &#8211; R$ 1.550,06 + R$ 350,00 (aux\u00edlio-sa\u00fade) + R$ 400,00* (aux\u00edlio-alimenta\u00e7\u00e3o).<\/li><li><strong><em>Agente Administrativo<\/em><\/strong> &#8211;<em><strong> 164 vagas &#8211;<\/strong><\/em> R$ 2.105,68 + R$ 350,00 (aux\u00edlio-sa\u00fade) + R$ 400,00* (aux\u00edlio-alimenta\u00e7\u00e3o) <\/li><li><strong><em>Agente de Cerimonial<\/em><\/strong> <em><strong>&#8211; 01 vaga <\/strong><\/em>-R$ 4.942,46 + R$ 350,00 (aux\u00edlio-sa\u00fade) + R$ 400,00 (aux\u00edlio-alimenta\u00e7\u00e3o)<\/li><li><strong><em>Agente Fiscal de Posturas<\/em><\/strong> <strong><em>&#8211; 15 vagas <\/em><\/strong>&#8211; R$ 4.942,46 +Reembolso Transporte (*) + Adicional de Produtividade: R$ 436,47 Produtividade vari\u00e1vel (<em>)+ R$ 350,00 (aux\u00edlio-sa\u00fade) + R$ 400,00<\/em> (aux\u00edlio-alimenta\u00e7\u00e3o)<\/li><li><strong><em>Arquiteto &#8211; 02 vagas &#8211;<\/em><\/strong>R$ 4.942,46+ R$ 350,00 (aux\u00edlio-sa\u00fade) +R$ 400,00 (aux\u00edlio-alimenta\u00e7\u00e3o)<\/li><li><strong><em>Engenheiro Agr\u00f4nomo <\/em><\/strong>&#8211; <strong><em>01 vaga<\/em><\/strong> &#8211; R$ 4.942,46 + R$ 350,00 (aux\u00edlio-sa\u00fade) + R$ 400,00 (aux\u00edlio-alimenta\u00e7\u00e3o)<\/li><li><strong><em>Engenheiro Civil &#8211; 10 vagas<\/em><\/strong> -R$ 4.942,46 +R$ 350,00 (aux\u00edlio-sa\u00fade) +R$ 400,00 (aux\u00edlio-alimenta\u00e7\u00e3o)<\/li><li><strong><em>Engenheiro Eletricista <\/em><\/strong>&#8211; <strong><em>01 vaga<\/em><\/strong> &#8211; R$ 4.942,46+ R$ 350,00 (aux\u00edlio-sa\u00fade) + R$ 400,00 (aux\u00edlio-alimenta\u00e7\u00e3o)<\/li><li><strong><em>Jornalista <\/em><\/strong>&#8211; <strong><em>01 vaga<\/em><\/strong> &#8211; R$ 4.942,46+R$ 350,00 (aux\u00edlio-sa\u00fade) + R$ 400,00 (aux\u00edlio-alimenta\u00e7\u00e3o)<\/li><li><strong><em>M\u00e9dico do Trabalho<\/em><\/strong> &#8211;<strong><em> 01 vaga<\/em><\/strong> &#8211;<strong>R$ 4.125,92<\/strong> + R$ 350,00 (aux\u00edlio-sa\u00fade) + R$ 400,00* (aux\u00edlio-alimenta\u00e7\u00e3o) &#8211;<strong> Valor retificado<\/strong><\/li><li><strong><em>T\u00e9cnico de Ilumina\u00e7\u00e3o<\/em><\/strong> <strong><em>&#8211; 03 vagas <\/em><\/strong>-R$ 2.105,68 + R$ 350,00 (aux\u00edlio-sa\u00fade)+R$ 400,00 (aux\u00edlio-alimenta\u00e7\u00e3o)<\/li><li><strong><em>T\u00e9cnico Seguran\u00e7a do Trabalho <\/em>&#8211; 01 vaga<\/strong> -R$ 2.105,68 +R$ 350,00 (aux\u00edlio-sa\u00fade)+R$ 400,00 (aux\u00edlio-alimenta\u00e7\u00e3o)<\/li><li><strong><em>T\u00e9cnico de Som <\/em><\/strong>&#8211; <strong><em>03 vagas <\/em><\/strong>-R$ 2.105,68 + R$ 350,00 (aux\u00edlio-sa\u00fade)+ R$ 400,00 (aux\u00edlio-alimenta\u00e7\u00e3o)<\/li><li><strong><em>Assistente Social <\/em><\/strong>&#8211;<strong><em> 01 vaga &#8211;<\/em><\/strong> R$ 4.942,46<\/li><li><strong><em>Psic\u00f3logo <\/em><\/strong>&#8211; <strong><em>01 vaga <\/em><\/strong>-R$ 4.942,46<\/li><li><strong><em>Agente Previdenci\u00e1rio<\/em><\/strong> &#8211; <strong><em>02 vagas<\/em><\/strong> -R$ 2.105,68<\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">As inscri\u00e7\u00f5es ser\u00e3o abertas no dia 08 de agosto e seguir\u00e3o at\u00e9 o dia 30, com taxa no valor de R$47 para os cargos de Agente de Combate \u00e0s Endemias e Agente Comunit\u00e1rio de Sa\u00fade, de R$55,00 para os cargos de n\u00edvel m\u00e9dio e R$75,00 para os cargos de n\u00edvel superior.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">As provas ser\u00e3o aplicadas na data prov\u00e1vel de 20 de outubro, realizadas na Cidade de S\u00e3o Jos\u00e9 do Rio Preto\/SP. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"text-align:center\"><strong>Gostou dessa oportunidade e quer saber mais sobre as vagas, cargos e etapas? Confira a mat\u00e9ria completa e saia na frente:<\/strong><\/p>\n\n\n\n<p style=\"text-align:center\" class=\"has-background has-medium-font-size has-light-green-cyan-background-color wp-block-paragraph\"><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-rio-preto\/\"><strong>Prefeitura de Rio Preto<\/strong><\/a><\/p>\n\n\n\n<h2 class=\"wp-block-heading\" style=\"text-align:center\" id=\"cursos-assinatura\">Quer estudar para o concurso da Prefeitura de Rio Preto SP?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"text-align:center\"><em>Gostou dessa oportunidade e deseja se preparar? Confira abaixo nossos cursos exclusivos para este concurso e inicie agora seus estudos! N\u00e3o fique de fora:<\/em><\/p>\n\n\n\n<p style=\"font-size:23px;text-align:center\" class=\"has-background has-luminous-vivid-amber-background-color wp-block-paragraph\"><span style=\"text-decoration: underline;\"><a rel=\"noreferrer noopener\" aria-label=\"Curso para concurso Prefeitura de Rio Preto SP (abre numa nova aba)\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/cursos\/concurso\/\" target=\"_blank\"><strong><em>Curso para concurso Prefeitura de Rio Preto SP<\/em><\/strong><\/a><\/span><\/p>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"text-align:center\"><em><strong>Assinatura Anual Ilimitada*<\/strong><\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"text-align:center\"><em>Prepare-se com o melhor material e com quem mais aprova em&nbsp;Concursos P\u00fablicos de todo o pa\u00eds. Assine agora a nossa Assinatura Anual e tenha acesso ilimitado* a todos os nossos cursos.<\/em><\/p>\n\n\n\n<p style=\"font-size:25px;text-align:center\" class=\"has-background has-light-green-cyan-background-color wp-block-paragraph\"><strong>ASSINE AGORA<\/strong>\u00a0\u2013\u00a0<a rel=\"noreferrer noopener\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/assinaturas\" target=\"_blank\"><strong>Assinatura Ilimitada<\/strong><\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ascom<br \/>ascomestrategia@gmail.com<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Foi publicada a primeira retifica\u00e7\u00e3o de um dos editais para o concurso da Prefeitura de S\u00e3o Jos\u00e9 do Rio Preto, munic\u00edpio de S\u00e3o Paulo. Nos primeiros dias de agosto foram publicados 05 editais, com um total de 349 vagas, para diversas \u00e1reas e n\u00edveis de forma\u00e7\u00e3o. Hoje, 06 de agosto, foi publicada uma retifica\u00e7\u00e3o alterando [&hellip;]<\/p>\n","protected":false},"author":260,"featured_media":400043,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"post_tipo":"article","footnotes":""},"categories":[1],"tags":[],"tax_estado":[],"class_list":["post-406610","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cursos-e-concursos"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Concurso Prefeitura de Rio Preto SP: Retifica\u00e7\u00e3o altera valor de remunera\u00e7\u00e3o<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-prefeitura-de-rio-preto-sp-retificacao-altera-valor-de-remuneracao\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Concurso Prefeitura de Rio Preto SP: Retifica\u00e7\u00e3o altera valor de remunera\u00e7\u00e3o\" \/>\n<meta property=\"og:description\" content=\"Foi publicada a primeira retifica\u00e7\u00e3o de um dos editais para o concurso da Prefeitura de S\u00e3o Jos\u00e9 do Rio Preto, munic\u00edpio de S\u00e3o Paulo. Nos primeiros dias de agosto foram publicados 05 editais, com um total de 349 vagas, para diversas \u00e1reas e n\u00edveis de forma\u00e7\u00e3o. Hoje, 06 de agosto, foi publicada uma retifica\u00e7\u00e3o alterando [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-prefeitura-de-rio-preto-sp-retificacao-altera-valor-de-remuneracao\/\" \/>\n<meta property=\"og:site_name\" content=\"Estrat\u00e9gia Concursos\" \/>\n<meta property=\"article:published_time\" content=\"2019-08-06T15:20:47+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-11-08T20:44:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2019\/07\/18070722\/CONCURSO-PREFEITURA-DE-RIO-PRETO.png\" \/>\n\t<meta property=\"og:image:width\" content=\"400\" \/>\n\t<meta property=\"og:image:height\" content=\"209\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Diego Cerqueira Berbert Vasconcelos\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:site\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Diego Cerqueira Berbert Vasconcelos\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/concurso-prefeitura-de-rio-preto-sp-retificacao-altera-valor-de-remuneracao\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/concurso-prefeitura-de-rio-preto-sp-retificacao-altera-valor-de-remuneracao\\\/\"},\"author\":{\"name\":\"Diego Cerqueira Berbert Vasconcelos\",\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/#\\\/schema\\\/person\\\/7fbf898fd336f5ce58a961518beff68c\"},\"headline\":\"Concurso Prefeitura de Rio Preto SP: Retifica\u00e7\u00e3o altera valor de remunera\u00e7\u00e3o\",\"datePublished\":\"2019-08-06T15:20:47+00:00\",\"dateModified\":\"2019-11-08T20:44:26+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/concurso-prefeitura-de-rio-preto-sp-retificacao-altera-valor-de-remuneracao\\\/\"},\"wordCount\":602,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/concurso-prefeitura-de-rio-preto-sp-retificacao-altera-valor-de-remuneracao\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dhg1h5j42swfq.cloudfront.net\\\/2019\\\/07\\\/18070722\\\/CONCURSO-PREFEITURA-DE-RIO-PRETO.png\",\"articleSection\":[\"Concursos P\u00fablicos\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/concurso-prefeitura-de-rio-preto-sp-retificacao-altera-valor-de-remuneracao\\\/#respond\"]}],\"copyrightYear\":\"2019\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/concurso-prefeitura-de-rio-preto-sp-retificacao-altera-valor-de-remuneracao\\\/\",\"url\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/concurso-prefeitura-de-rio-preto-sp-retificacao-altera-valor-de-remuneracao\\\/\",\"name\":\"Concurso Prefeitura de Rio Preto SP: Retifica\u00e7\u00e3o altera valor de remunera\u00e7\u00e3o\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/concurso-prefeitura-de-rio-preto-sp-retificacao-altera-valor-de-remuneracao\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/concurso-prefeitura-de-rio-preto-sp-retificacao-altera-valor-de-remuneracao\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dhg1h5j42swfq.cloudfront.net\\\/2019\\\/07\\\/18070722\\\/CONCURSO-PREFEITURA-DE-RIO-PRETO.png\",\"datePublished\":\"2019-08-06T15:20:47+00:00\",\"dateModified\":\"2019-11-08T20:44:26+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/concurso-prefeitura-de-rio-preto-sp-retificacao-altera-valor-de-remuneracao\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/concurso-prefeitura-de-rio-preto-sp-retificacao-altera-valor-de-remuneracao\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/concurso-prefeitura-de-rio-preto-sp-retificacao-altera-valor-de-remuneracao\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dhg1h5j42swfq.cloudfront.net\\\/2019\\\/07\\\/18070722\\\/CONCURSO-PREFEITURA-DE-RIO-PRETO.png\",\"contentUrl\":\"https:\\\/\\\/dhg1h5j42swfq.cloudfront.net\\\/2019\\\/07\\\/18070722\\\/CONCURSO-PREFEITURA-DE-RIO-PRETO.png\",\"width\":400,\"height\":209,\"caption\":\"CONCURSO RIO PRETO SP\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/concurso-prefeitura-de-rio-preto-sp-retificacao-altera-valor-de-remuneracao\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Concurso Prefeitura de Rio Preto SP: Retifica\u00e7\u00e3o altera valor de remunera\u00e7\u00e3o\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/\",\"name\":\"Estrat\u00e9gia Concursos\",\"description\":\"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/#organization\",\"name\":\"Estrat\u00e9gia Concursos\",\"url\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dhg1h5j42swfq.cloudfront.net\\\/2025\\\/06\\\/03203428\\\/logo_concursos-1.jpg\",\"contentUrl\":\"https:\\\/\\\/dhg1h5j42swfq.cloudfront.net\\\/2025\\\/06\\\/03203428\\\/logo_concursos-1.jpg\",\"width\":230,\"height\":60,\"caption\":\"Estrat\u00e9gia Concursos\"},\"image\":{\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/EstratConcursos\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/#\\\/schema\\\/person\\\/7fbf898fd336f5ce58a961518beff68c\",\"name\":\"Diego Cerqueira Berbert Vasconcelos\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ed2d045a7390980cad1a92d24dcc39d10ef55b88fcb9fb9c047979bf4ddeb1ce?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ed2d045a7390980cad1a92d24dcc39d10ef55b88fcb9fb9c047979bf4ddeb1ce?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ed2d045a7390980cad1a92d24dcc39d10ef55b88fcb9fb9c047979bf4ddeb1ce?s=96&d=mm&r=g\",\"caption\":\"Diego Cerqueira Berbert Vasconcelos\"},\"url\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/author\\\/diegocerqueiraestrategiaconcursos-com-br\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Concurso Prefeitura de Rio Preto SP: Retifica\u00e7\u00e3o altera valor de remunera\u00e7\u00e3o","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-prefeitura-de-rio-preto-sp-retificacao-altera-valor-de-remuneracao\/","og_locale":"pt_BR","og_type":"article","og_title":"Concurso Prefeitura de Rio Preto SP: Retifica\u00e7\u00e3o altera valor de remunera\u00e7\u00e3o","og_description":"Foi publicada a primeira retifica\u00e7\u00e3o de um dos editais para o concurso da Prefeitura de S\u00e3o Jos\u00e9 do Rio Preto, munic\u00edpio de S\u00e3o Paulo. Nos primeiros dias de agosto foram publicados 05 editais, com um total de 349 vagas, para diversas \u00e1reas e n\u00edveis de forma\u00e7\u00e3o. Hoje, 06 de agosto, foi publicada uma retifica\u00e7\u00e3o alterando [&hellip;]","og_url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-prefeitura-de-rio-preto-sp-retificacao-altera-valor-de-remuneracao\/","og_site_name":"Estrat\u00e9gia Concursos","article_published_time":"2019-08-06T15:20:47+00:00","article_modified_time":"2019-11-08T20:44:26+00:00","og_image":[{"width":400,"height":209,"url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2019\/07\/18070722\/CONCURSO-PREFEITURA-DE-RIO-PRETO.png","type":"image\/png"}],"author":"Diego Cerqueira Berbert Vasconcelos","twitter_card":"summary_large_image","twitter_creator":"@EstratConcursos","twitter_site":"@EstratConcursos","twitter_misc":{"Escrito por":"Diego Cerqueira Berbert Vasconcelos","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-prefeitura-de-rio-preto-sp-retificacao-altera-valor-de-remuneracao\/#article","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-prefeitura-de-rio-preto-sp-retificacao-altera-valor-de-remuneracao\/"},"author":{"name":"Diego Cerqueira Berbert Vasconcelos","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/7fbf898fd336f5ce58a961518beff68c"},"headline":"Concurso Prefeitura de Rio Preto SP: Retifica\u00e7\u00e3o altera valor de remunera\u00e7\u00e3o","datePublished":"2019-08-06T15:20:47+00:00","dateModified":"2019-11-08T20:44:26+00:00","mainEntityOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-prefeitura-de-rio-preto-sp-retificacao-altera-valor-de-remuneracao\/"},"wordCount":602,"commentCount":0,"publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-prefeitura-de-rio-preto-sp-retificacao-altera-valor-de-remuneracao\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2019\/07\/18070722\/CONCURSO-PREFEITURA-DE-RIO-PRETO.png","articleSection":["Concursos P\u00fablicos"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-prefeitura-de-rio-preto-sp-retificacao-altera-valor-de-remuneracao\/#respond"]}],"copyrightYear":"2019","copyrightHolder":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-prefeitura-de-rio-preto-sp-retificacao-altera-valor-de-remuneracao\/","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-prefeitura-de-rio-preto-sp-retificacao-altera-valor-de-remuneracao\/","name":"Concurso Prefeitura de Rio Preto SP: Retifica\u00e7\u00e3o altera valor de remunera\u00e7\u00e3o","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-prefeitura-de-rio-preto-sp-retificacao-altera-valor-de-remuneracao\/#primaryimage"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-prefeitura-de-rio-preto-sp-retificacao-altera-valor-de-remuneracao\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2019\/07\/18070722\/CONCURSO-PREFEITURA-DE-RIO-PRETO.png","datePublished":"2019-08-06T15:20:47+00:00","dateModified":"2019-11-08T20:44:26+00:00","breadcrumb":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-prefeitura-de-rio-preto-sp-retificacao-altera-valor-de-remuneracao\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-prefeitura-de-rio-preto-sp-retificacao-altera-valor-de-remuneracao\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-prefeitura-de-rio-preto-sp-retificacao-altera-valor-de-remuneracao\/#primaryimage","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2019\/07\/18070722\/CONCURSO-PREFEITURA-DE-RIO-PRETO.png","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2019\/07\/18070722\/CONCURSO-PREFEITURA-DE-RIO-PRETO.png","width":400,"height":209,"caption":"CONCURSO RIO PRETO SP"},{"@type":"BreadcrumbList","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-prefeitura-de-rio-preto-sp-retificacao-altera-valor-de-remuneracao\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.estrategiaconcursos.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Concurso Prefeitura de Rio Preto SP: Retifica\u00e7\u00e3o altera valor de remunera\u00e7\u00e3o"}]},{"@type":"WebSite","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","name":"Estrat\u00e9gia Concursos","description":"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.","publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization","name":"Estrat\u00e9gia Concursos","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","width":230,"height":60,"caption":"Estrat\u00e9gia Concursos"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/EstratConcursos"]},{"@type":"Person","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/7fbf898fd336f5ce58a961518beff68c","name":"Diego Cerqueira Berbert Vasconcelos","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/ed2d045a7390980cad1a92d24dcc39d10ef55b88fcb9fb9c047979bf4ddeb1ce?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ed2d045a7390980cad1a92d24dcc39d10ef55b88fcb9fb9c047979bf4ddeb1ce?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ed2d045a7390980cad1a92d24dcc39d10ef55b88fcb9fb9c047979bf4ddeb1ce?s=96&d=mm&r=g","caption":"Diego Cerqueira Berbert Vasconcelos"},"url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/diegocerqueiraestrategiaconcursos-com-br\/"}]}},"_links":{"self":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/406610","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/users\/260"}],"replies":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/comments?post=406610"}],"version-history":[{"count":0,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/406610\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media\/400043"}],"wp:attachment":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media?parent=406610"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/categories?post=406610"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tags?post=406610"},{"taxonomy":"tax_estado","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tax_estado?post=406610"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}